{"id":17261,"date":"2026-08-05T20:13:38","date_gmt":"2026-08-05T11:13:38","guid":{"rendered":"https:\/\/adc-thailand.com\/thailand\/?p=17261"},"modified":"2026-08-05T20:13:38","modified_gmt":"2026-08-05T11:13:38","slug":"%e3%82%bf%e3%82%a4%e3%81%a72026%e5%b9%b47%e6%9c%88%e3%81%ab%e6%96%b0%e8%a6%8f%e7%99%bb%e8%a8%98%e3%81%95%e3%82%8c%e3%81%9f%e6%b3%95%e4%ba%ba%e3%83%aa%e3%82%b9%e3%83%88","status":"publish","type":"post","link":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html","title":{"rendered":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8"},"content":{"rendered":"<div class=\"adc-nrc adc-nrc--cards\" id=\"adc-nrc-2607-2746deb9\">\n                <div class=\"adc-nrc__head\">\n                    <h2 class=\"adc-nrc__title\">\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8<\/h2>\n                    <p class=\"adc-nrc__meta\">\n                        \u8868\u793a\u5bfe\u8c61\uff1a7,512\u4ef6\u3002\n                        \u521d\u671f\u8868\u793a\u306f\u8cc7\u672c\u91d1\u306e\u5927\u304d\u3044\u9806\u3067\u3059\u3002\n                    <\/p>\n                <\/div>\n\n                <div class=\"adc-nrc__toolbar\" aria-label=\"\u4e00\u89a7\u306e\u7d5e\u308a\u8fbc\u307f\u3068\u4e26\u3073\u66ff\u3048\">\n                                        <label class=\"adc-nrc__control adc-nrc__control--search\">\n                        <span>\u691c\u7d22<\/span>\n                        <input type=\"search\" class=\"adc-nrc__search\" placeholder=\"\u6cd5\u4eba\u756a\u53f7\u30fb\u793e\u540d\u30fb\u4f4f\u6240\u30fb\u696d\u7a2e\u306a\u3069\" autocomplete=\"off\">\n                    <\/label>\n                                        <label class=\"adc-nrc__control\">\n                        <span>\u696d\u7a2e<\/span>\n                        <select class=\"adc-nrc__industry-filter\">\n                            <option value=\"\">\u3059\u3079\u3066<\/option>\n                        <\/select>\n                    <\/label>\n                    <label class=\"adc-nrc__control\">\n                        <span>\u4e26\u3073\u9806<\/span>\n                        <select class=\"adc-nrc__sort\">\n                            <option value=\"capital_desc\">\u8cc7\u672c\u91d1\u304c\u5927\u304d\u3044\u9806<\/option>\n                            <option value=\"capital_asc\">\u8cc7\u672c\u91d1\u304c\u5c0f\u3055\u3044\u9806<\/option>\n                            <option value=\"date_desc\">\u767b\u8a18\u65e5\u304c\u65b0\u3057\u3044\u9806<\/option>\n                            <option value=\"date_asc\">\u767b\u8a18\u65e5\u304c\u53e4\u3044\u9806<\/option>\n                            <option value=\"regno_asc\">\u6cd5\u4eba\u756a\u53f7\u9806<\/option>\n                        <\/select>\n                    <\/label>\n                    <label class=\"adc-nrc__control adc-nrc__control--per-page\">\n                        <span>\u8868\u793a\u4ef6\u6570<\/span>\n                        <select class=\"adc-nrc__per-page\">\n                            <option value=\"50\">50\u4ef6<\/option>\n                            <option value=\"100\" selected='selected'>100\u4ef6<\/option>\n                            <option value=\"200\">200\u4ef6<\/option>\n                            <option value=\"500\">500\u4ef6<\/option>\n                        <\/select>\n                    <\/label>\n                <\/div>\n\n                <div class=\"adc-nrc__status\" aria-live=\"polite\"><\/div>\n                <div class=\"adc-nrc__cards\" aria-live=\"polite\"><\/div>\n                <div class=\"adc-nrc__pager\" aria-label=\"\u30da\u30fc\u30b8\u5207\u308a\u66ff\u3048\"><\/div>\n\n                <p class=\"adc-nrc__footnote\">\u3053\u306e\u4e00\u89a7\u306f\u516c\u958bCSV\u3092\u3082\u3068\u306b\u3057\u305f\u53c2\u8003\u8868\u793a\u3067\u3059\u3002\u6b63\u5f0f\u306a\u767b\u8a18\u5185\u5bb9\u30fb\u55b6\u696d\u72b6\u614b\u30fb\u682a\u4e3b\u60c5\u5831\u306a\u3069\u306fDBD\u66f8\u985e\u3067\u78ba\u8a8d\u3057\u3066\u304f\u3060\u3055\u3044\u3002<\/p>\n                <script type=\"application\/json\" class=\"adc-nrc__data\">[{\"reg_no\":\"0107569000152\",\"name_th\":\"\u0e1a\u0e21\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":40496219730,\"capital_display\":\"40,496,219,730 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0107569000152 \u0e1a\u0e21\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) 2569-07-31 40496219730 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1550  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e18\u0e19\u0e20\u0e39\u0e21\u0e34 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 27 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140611\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e0d\u0e08\u0e23\u0e32\u0e0a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":400000000,\"capital_display\":\"400,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140611 \u0e1a\u0e08.\u0e40\u0e1a\u0e0d\u0e08\u0e23\u0e32\u0e0a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 400000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e02\u0e22\u0e30  \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 227  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e32\u0e29\u0e0f\u0e23\u0e4c1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024190\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e2e\u0e47\u0e2d\u0e1a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)         \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":250000000,\"capital_display\":\"250,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32501\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32501\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024190 \u0e1a\u0e08.\u0e2d\u0e35\u0e2e\u0e47\u0e2d\u0e1a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)         \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 250000000 32501 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e41\u0e1c\u0e25\u0e01\u0e14\u0e17\u0e31\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e41\u0e25\u0e30\u0e22\u0e01\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 777\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569131204\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e08\u0e35\u0e42\u0e2d \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":111750000,\"capital_display\":\"111,750,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131204 \u0e1a\u0e08.\u0e17\u0e35\u0e08\u0e35\u0e42\u0e2d \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 111750000 46691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e04\u0e21\u0e35 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 230  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139345\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e0b\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000000,\"capital_display\":\"100,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139345 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e0b\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e15\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e25\u0e39\u0e0a\u0e34\u0e1e\u0e2a\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 402\u0e40\u0e23\u0e2a\u0e42\u0e0409 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d 10) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126944\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e35\u0e1b\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000000,\"capital_display\":\"100,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126944 \u0e1a\u0e08.\u0e25\u0e35\u0e1b\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e40\u0e1e\u0e25\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 16 \u0e22\u0e39\u0e19\u0e34\u0e15 1603-1606 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569036987\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e2d\u0e07\u0e38\u0e48\u0e19\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 (2569) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":90000000,\"capital_display\":\"90,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036987 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e2d\u0e07\u0e38\u0e48\u0e19\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 (2569) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 90000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u4e0d\u52d5\u7523 20  \u0e0b\u0e2d\u0e22 \u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35-\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e36\u0e07 21 \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35-\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e36\u0e07 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037835\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e39\u0e21\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":64000000,\"capital_display\":\"64,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037835 \u0e1a\u0e08.\u0e17\u0e23\u0e39\u0e21\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 64000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 46\/131   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037037\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e15\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":56000000,\"capital_display\":\"56,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037037 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e15\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 56000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 46\/131   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0115569024688\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e1a\u0e1a\u0e35\u0e49 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e27\u0e39\u0e49\u0e14\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":50000000,\"capital_display\":\"50,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024688 \u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e1a\u0e1a\u0e35\u0e49 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e27\u0e39\u0e49\u0e14\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 50000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u88fd\u9020 46\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569138730\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e20\u0e31\u0e04 18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":50000000,\"capital_display\":\"50,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138730 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e20\u0e31\u0e04 18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 50000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2a\u0e27\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e19\u0e34\u0e04\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e48\u0e2d\u0e22 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e42\u0e2d\u0e19 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e17\u0e32\u0e07 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u4e0d\u52d5\u7523 59  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138748\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e20\u0e31\u0e04 19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":50000000,\"capital_display\":\"50,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138748 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e20\u0e31\u0e04 19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 50000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2a\u0e27\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e19\u0e34\u0e04\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e48\u0e2d\u0e22 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e42\u0e2d\u0e19 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e17\u0e32\u0e07 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u4e0d\u52d5\u7523 59  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138756\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e20\u0e31\u0e04 20 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":50000000,\"capital_display\":\"50,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138756 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e20\u0e31\u0e04 20 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 50000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2a\u0e27\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e19\u0e34\u0e04\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e48\u0e2d\u0e22 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e42\u0e2d\u0e19 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e17\u0e32\u0e07 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u4e0d\u52d5\u7523 59  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131565\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e1e\u0e31\u0e25 \u0e1e\u0e32\u0e40\u0e25\u0e17 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":50000000,\"capital_display\":\"50,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23941\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23941\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131565 \u0e1a\u0e08.\u0e23\u0e35\u0e1e\u0e31\u0e25 \u0e1e\u0e32\u0e40\u0e25\u0e17 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 50000000 23941 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u88fd\u9020 491\/1  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132723\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e35\u0e22\u0e23\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":47300000,\"capital_display\":\"47,300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132723 \u0e1a\u0e08.\u0e40\u0e25\u0e35\u0e22\u0e23\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 47300000 27200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e31\u0e27\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e31\u0e27\u0e19\u0e33\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e42\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u88fd\u9020 29  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569034631\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e14\u0e2a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":44000000,\"capital_display\":\"44,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034631 \u0e1a\u0e08.\u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e14\u0e2a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 44000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 46\/131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569139159\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e0a\u0e0b\u0e35 \u0e40\u0e2d\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":32000000,\"capital_display\":\"32,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139159 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e0a\u0e0b\u0e35 \u0e40\u0e2d\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 32000000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u6559\u80b2 49  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e34\u0e08 \u0e0b\u0e2d\u0e22 \u0e2a\u0e35\u0e25\u0e21 3 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0215569008801\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e0a\u0e34\u0e1b\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":32000000,\"capital_display\":\"32,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"30110\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"30110\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008801 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e0a\u0e34\u0e1b\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 32000000 30110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e23\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d \u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e23\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e02\u0e19\u0e32\u0e14 \u88fd\u9020 5\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005173\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e2b\u0e21\u0e34\u0e15\u0e23 2482\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":30000000,\"capital_display\":\"30,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005173 \u0e2b\u0e08.\u0e2a\u0e2b\u0e21\u0e34\u0e15\u0e23 2482 2569-07-23 30000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u4e0d\u52d5\u7523 29\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016533\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a \u0e40\u0e14\u0e25\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":30000000,\"capital_display\":\"30,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016533 \u0e1a\u0e08.\u0e23\u0e34\u0e0a \u0e40\u0e14\u0e25\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 30000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 53\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0125569026516\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e25\u0e08\u0e34\u0e2a \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":30000000,\"capital_display\":\"30,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026516 \u0e1a\u0e08.\u0e42\u0e25\u0e08\u0e34\u0e2a \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 30000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1e\u0e31\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e34\u0e14\u0e09\u0e25\u0e32\u0e01 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 55\/56-58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569143016\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e08\u0e42\u0e0b\u0e48 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":25000000,\"capital_display\":\"25,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"26103\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"26103\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143016 \u0e1a\u0e08.\u0e42\u0e08\u0e42\u0e0b\u0e48 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 25000000 26103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1c\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e2a\u0e39\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e21\u0e32\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e40\u0e08\u0e32\u0e30 \u0e15\u0e31\u0e14 \u0e40\u0e08\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e15\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e14 \u0e40\u0e0b\u0e32\u0e30\u0e23\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e27\u0e35\u0e04\u0e31\u0e17 \u0e15\u0e31\u0e14\u0e41\u0e19\u0e27\u0e02\u0e2d\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e1a\u0e22\u0e36\u0e14\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 123  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e35.\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 34 \u0e22\u0e39\u0e19\u0e34\u0e15 3404 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134751\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e22\u0e23\u0e32 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":20000000,\"capital_display\":\"20,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134751 \u0e1a\u0e08.\u0e44\u0e2d\u0e22\u0e23\u0e32 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 20000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 126  \u0e0b\u0e2d\u0e22 \u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c 16 \u0e16\u0e19\u0e19\u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134831\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":20000000,\"capital_display\":\"20,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134831 \u0e1a\u0e08.\u0e44\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 20000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e42\u0e14\u0e22\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e1b\u0e31\u0e19\u0e1c\u0e25 \u91d1\u878d\u30fb\u4fdd\u967a 12  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e25\u0e14\u0e34\u0e4c 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131646\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e04\u0e01\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":20000000,\"capital_display\":\"20,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131646 \u0e1a\u0e08.\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e04\u0e01\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 20000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e25\u0e32\u0e19\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e33\u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e27\u0e19\u0e23\u0e16 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2d\u0e37\u0e48\u0e19 \u0e46  \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 238\/7  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130143\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e25 21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":20000000,\"capital_display\":\"20,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130143 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e25 21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 20000000 68102 \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e1a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e0b\u0e36\u0e48\u0e07 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e43\u0e2b\u0e49 \u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e42\u0e2d\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49 \u0e42\u0e2d\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e28\u0e32\u0e25 \u0e42\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e1a\u0e48\u0e07\u0e2b\u0e31\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e08\u0e31\u0e14\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e19\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1b\u0e27\u0e32\u0e07\u0e04\u0e4d\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e44\u0e14\u0e49\u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15 \u0e1f\u0e2d\u0e07\u0e0b\u0e34\u0e40\u0e2d\u0e23\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19) \u4e0d\u52d5\u7523 989  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569021239\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e30\u0e21\u0e38\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e41\u0e04\u0e23\u0e4c 26 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":20000000,\"capital_display\":\"20,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47999\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47999\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021239 \u0e1a\u0e08.\u0e25\u0e30\u0e21\u0e38\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e41\u0e04\u0e23\u0e4c 26 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 20000000 47999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e41\u0e21\u0e48 \u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e2d\u0e32\u0e17\u0e34\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0635569001390\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e1a\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e44\u0e2d\u0e0b\u0e4c \u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":20000000,\"capital_display\":\"20,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10795\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10795\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001390 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e1a\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e44\u0e2d\u0e0b\u0e4c \u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 20000000 10795 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u88fd\u9020 444  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0115569021883\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":20000000,\"capital_display\":\"20,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33141\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33141\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021883 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 20000000 33141 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e33\u0e08\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e23\u0e2d\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e15\u0e31\u0e27 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46   \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e40\u0e17\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e19\u0e49\u0e33\u0e43\u0e0a\u0e49  \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33  \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33\u0e23\u0e49\u0e2d\u0e19  \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e2d\u0e19\u0e49\u0e33  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23 \u0e27\u0e32\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u88fd\u9020 88\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0107569000144\",\"name_th\":\"\u0e1a\u0e21\u0e08.\u0e2a\u0e44\u0e1b\u0e0b\u0e35\u0e48 \u0e41\u0e04\u0e17 \u0e40\u0e2d\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":18573300,\"capital_display\":\"18,573,300 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0107569000144 \u0e1a\u0e21\u0e08.\u0e2a\u0e44\u0e1b\u0e0b\u0e35\u0e48 \u0e41\u0e04\u0e17 \u0e40\u0e2d\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) 2569-07-15 18573300 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 10\/32 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138004\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e42\u0e14\u0e04\u0e32\u0e27\u0e30 \u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":15000000,\"capital_display\":\"15,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138004 \u0e1a\u0e08.\u0e04\u0e32\u0e42\u0e14\u0e04\u0e32\u0e27\u0e30 \u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 15000000 70209 \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e44\u0e2d\u0e17\u0e35 \u0e41\u0e01\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\/\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e48\u0e2d\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/129  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25 \u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32 \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 of22202 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 22 \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124186\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e40\u0e21\u0e32\u0e19\u0e4c\u0e40\u0e17\u0e19 \u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":15000000,\"capital_display\":\"15,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96301\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96301\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124186 \u0e1a\u0e08.\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e40\u0e21\u0e32\u0e19\u0e4c\u0e40\u0e17\u0e19 \u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 15000000 96301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e38\u0e2a\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e1e\u0e31\u0e01\u0e28\u0e1e \u0e1d\u0e31\u0e07 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1c\u0e32\u0e28\u0e1e \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2b\u0e25\u0e38\u0e21\u0e1d\u0e31\u0e07\u0e28\u0e1e \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2e\u0e27\u0e07\u0e0b\u0e38\u0e49\u0e22 (\u0e15\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21\u0e08\u0e35\u0e19) \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1d\u0e31\u0e07 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1c\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e25\u0e07\u0e28\u0e1e \u0e42\u0e01\u0e28 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e49\u0e19\u0e44\u0e2b\u0e27\u0e49 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 8\/12  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e1544 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143300\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e23\u0e30 \u0e0b\u0e39\u0e0a\u0e34 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":14000000,\"capital_display\":\"14,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143300 \u0e1a\u0e08.\u0e04\u0e38\u0e23\u0e30 \u0e0b\u0e39\u0e0a\u0e34 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 14000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 129  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 02 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12\u0e40\u0e2d \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024491\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e25\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":12000000,\"capital_display\":\"12,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024491 \u0e1a\u0e08.\u0e42\u0e1f\u0e25\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 12000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 222\/83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569124640\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":12000000,\"capital_display\":\"12,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124640 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 12000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 2  \u0e0b\u0e2d\u0e22 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028390\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e38\u0e19\u0e17\u0e2d\u0e07 \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028390 \u0e1a\u0e08.\u0e02\u0e38\u0e19\u0e17\u0e2d\u0e07 \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 10000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 33\/1  \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c 48 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569141595\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141595 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 10000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c (\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c) \u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u4e0d\u52d5\u7523 242  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 19\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0215569009980\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48 \u0e2d\u0e49\u0e32\u0e22 \u0e44\u0e17\u0e48 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009980 \u0e1a\u0e08.\u0e44\u0e17\u0e48 \u0e2d\u0e49\u0e32\u0e22 \u0e44\u0e17\u0e48 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 10000000 78109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 361\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009998\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009998 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 10000000 46521 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e44\u0e14\u0e49\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016789\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e27\u0e07 \u0e25\u0e39\u0e21 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016789 \u0e1a\u0e08.\u0e2b\u0e25\u0e27\u0e07 \u0e25\u0e39\u0e21 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 10000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2a\u0e1b\u0e32 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e32 \u5bbf\u6cca\u30fb\u98f2\u98df 624  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0205569038904\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e17\u0e23\u0e32 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038904 \u0e1a\u0e08.\u0e40\u0e27\u0e17\u0e23\u0e32 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 10000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569139116\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139116 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 10000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e16\u0e22\u0e37\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e01\u0e39\u0e4a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 191\/88  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139221\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e49\u0e32\u0e41\u0e17\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139221 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e49\u0e32\u0e41\u0e17\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 10000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e1a\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 238\/7  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569037649\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e23\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66123\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66123\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037649 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e23\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 10000000 66123 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28(\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u91d1\u878d\u30fb\u4fdd\u967a 159\/272  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009491\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e21\u0e39 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009491 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e21\u0e39 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 10000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 38  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e32\u0e07\u0e28\u0e23\u0e35 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569133959\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e19\u0e14\u0e23\u0e49\u0e32 \u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133959 \u0e1a\u0e08.\u0e0b\u0e32\u0e19\u0e14\u0e23\u0e49\u0e32 \u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 10000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 21 \u0e41\u0e22\u0e01 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0405569006865\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e1f \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006865 \u0e1a\u0e08.\u0e25\u0e39\u0e1f \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 10000000 45101 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/1-4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569132847\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132847 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 10000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 689  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e20\u0e34\u0e23\u0e31\u0e0a\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e17 \u0e40\u0e2d\u0e47\u0e21\u0e04\u0e27\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133398\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e15\u0e2a\u0e40\u0e1b\u0e0b \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46433\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46433\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133398 \u0e1a\u0e08.\u0e1f\u0e34\u0e15\u0e2a\u0e40\u0e1b\u0e0b \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 10000000 46433 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e17\u0e23 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569037223\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e22\u0e2d\u0e0a\u0e17\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"50212\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"50212\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037223 \u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e22\u0e2d\u0e0a\u0e17\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 10000000 50212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e22\u0e2d\u0e23\u0e4c\u0e0a \u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e23\u0e32\u0e0d \u0e40\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e47\u0e27 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 407\/97  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569132448\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132448 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 10000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 167\/1  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 49 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026214\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e19\u0e0b\u0e2d\u0e27\u0e4c \u0e17\u0e39\u0e1b\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22230\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22230\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026214 \u0e1a\u0e08.\u0e40\u0e17\u0e19\u0e0b\u0e2d\u0e27\u0e4c \u0e17\u0e39\u0e1b\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 10000000 22230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e22\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 101\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569130071\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c 8000 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130071 \u0e1a\u0e08.\u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c 8000 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 10000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e1b\u0e25\u0e35\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 65 \u0e41\u0e22\u0e01 15-4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0745569007192\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e23\u0e31\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007192 \u0e1a\u0e08.\u0e1a\u0e35\u0e23\u0e31\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 10000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data center) \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 43\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569005422\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e23\u0e34\u0e42\u0e01\u0e25\u0e14\u0e4c  \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005422 \u0e1a\u0e08.\u0e41\u0e21\u0e23\u0e34\u0e42\u0e01\u0e25\u0e14\u0e4c  \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 10000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 999\/9  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e44\u0e17\u0e22-\u0e08\u0e31\u0e07\u0e42\u0e2b\u0e25\u0e19 22 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569127410\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e0b\u0e47\u0e19 \u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127410 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e0b\u0e47\u0e19 \u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 10000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 55\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569025153\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e23\u0e47\u0e15\u0e1a\u0e23\u0e34\u0e27\u0e2d\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025153 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e23\u0e47\u0e15\u0e1a\u0e23\u0e34\u0e27\u0e2d\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 10000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21 \u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035239\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e19\u0e01 \u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035239 \u0e1a\u0e08.\u0e01\u0e19\u0e01 \u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 10000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 385\/16   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003591\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e04\u0e32\u0e40\u0e1f\u0e48 (2011) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003591 \u0e1a\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e04\u0e32\u0e40\u0e1f\u0e48 (2011) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 10000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0705569002999\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e24\u0e15\u0e08\u0e34\u0e23\u0e17\u0e31\u0e15 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":10000000,\"capital_display\":\"10,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569002999 \u0e1a\u0e08.\u0e01\u0e24\u0e15\u0e08\u0e34\u0e23\u0e17\u0e31\u0e15 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 10000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 53\/14  \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e32\u0e01\u0e41\u0e23\u0e15 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569134807\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":8800000,\"capital_display\":\"8,800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134807 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 8800000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2556  \u0e2d\u0e32\u0e04\u0e32\u0e2366 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0745569007389\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e0b\u0e35\u0e1f\u0e32 \u0e44\u0e2d\u0e40\u0e2d\u0e01\u0e0b\u0e4c\u0e17\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":8750000,\"capital_display\":\"8,750,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007389 \u0e1a\u0e08.\u0e2d\u0e32\u0e0b\u0e35\u0e1f\u0e32 \u0e44\u0e2d\u0e40\u0e2d\u0e01\u0e0b\u0e4c\u0e17\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 8750000 63111 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data center) \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569141706\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e17\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":8000000,\"capital_display\":\"8,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10772\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10772\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141706 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e17\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 8000000 10772 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e0b\u0e2d\u0e2a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e0b\u0e2d\u0e2a\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e2a\u0e1e\u0e23\u0e34\u0e01 \u0e0b\u0e2d\u0e2a\u0e1c\u0e31\u0e14 \u0e1a\u0e32\u0e1a\u0e35\u0e04\u0e34\u0e27\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21\u0e2a\u0e32\u0e22\u0e0a\u0e39 \u0e19\u0e49\u0e33\u0e21\u0e32\u0e22\u0e2d\u0e07\u0e40\u0e19\u0e2a \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 767  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e44\u0e1c\u0e48\u0e40\u0e07\u0e34\u0e19 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e14\u0e44\u0e1c\u0e48\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0745569007672\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e08 \u0e41\u0e1a\u0e19\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":8000000,\"capital_display\":\"8,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007672 \u0e1a\u0e08.\u0e40\u0e2d\u0e08 \u0e41\u0e1a\u0e19\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 8000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e34\u0e14\u0e02\u0e2d\u0e1a \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e34\u0e14\u0e02\u0e2d\u0e1a\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e34\u0e14\u0e02\u0e2d\u0e1a\u0e44\u0e21\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e34\u0e14\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u88fd\u9020 51\/38-39 , 51\/46-47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569034704\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":8000000,\"capital_display\":\"8,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034704 \u0e1a\u0e08.\u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 8000000 68102 \u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e25\u0e07\u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u4e0d\u52d5\u7523 8\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569138322\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e39\u0e01\u0e32\u0e40\u0e21\u0e30 \u0e2d\u0e38\u0e14\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":7500000,\"capital_display\":\"7,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138322 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e39\u0e01\u0e32\u0e40\u0e21\u0e30 \u0e2d\u0e38\u0e14\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 7500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e49\u0e19\u0e2d\u0e38\u0e14\u0e49\u0e07 \u0e40\u0e17\u0e21\u0e1b\u0e38\u0e23\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e2a\u0e21\u0e34\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133975\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e25\u0e15\u0e31\u0e2a \u0e2d\u0e30\u0e0b\u0e31\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":7440000,\"capital_display\":\"7,440,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86902\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86902\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133975 \u0e1a\u0e08.\u0e42\u0e25\u0e15\u0e31\u0e2a \u0e2d\u0e30\u0e0b\u0e31\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 7440000 86902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e42\u0e14\u0e22\u0e19\u0e31\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e42\u0e01\u0e40\u0e18\u0e2d\u0e23\u0e32\u0e1e\u0e35 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e41\u0e1a\u0e1a\u0e44\u0e04\u0e42\u0e23\u0e41\u0e1e\u0e23\u0e04\u0e15\u0e34\u0e04 \u0e2f\u0e25\u0e2f \u533b\u7642\u30fb\u798f\u7949 89  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569022782\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e34\u0e19 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":7000000,\"capital_display\":\"7,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022782 \u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e34\u0e19 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 7000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1a\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 60\/125  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e19\u0e27\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a-17, a-18 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569130526\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e40\u0e27\u0e48\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":7000000,\"capital_display\":\"7,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130526 \u0e1a\u0e08.\u0e40\u0e2e\u0e40\u0e27\u0e48\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 7000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u533b\u7642\u30fb\u798f\u7949 60  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 19 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027521\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e0469 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":6000000,\"capital_display\":\"6,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86102\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86102\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027521 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e0469 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 6000000 86102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1f\u0e2d\u0e01\u0e40\u0e25\u0e37\u0e2d\u0e14 \u0e25\u0e49\u0e32\u0e07\u0e44\u0e15\u0e04\u0e19\u0e44\u0e02\u0e49\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e23\u0e04\u0e44\u0e15\u0e27\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 435\/1  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c 22 \u0e41\u0e22\u0e01 1 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009637\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e14\u0e35  \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":6000000,\"capital_display\":\"6,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009637 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e14\u0e35  \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 6000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 19\/51  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569133967\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e15\u0e34 \u0e2d\u0e39\u0e23\u0e4c \u0e40\u0e23\u0e2b\u0e4c\u0e21\u0e32\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":6000000,\"capital_display\":\"6,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133967 \u0e1a\u0e08.\u0e21\u0e39\u0e15\u0e34 \u0e2d\u0e39\u0e23\u0e4c \u0e40\u0e23\u0e2b\u0e4c\u0e21\u0e32\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 6000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 21 \u0e41\u0e22\u0e01 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022804\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e27\u0e32\u0e04\u0e2d\u0e21 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":6000000,\"capital_display\":\"6,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022804 \u0e1a\u0e08.\u0e2e\u0e27\u0e32\u0e04\u0e2d\u0e21 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 6000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 954\/1724  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e21\u0e42\u0e17\u0e23\u0e42\u0e1e\u0e25\u0e34\u0e2a \u0e2a\u0e33\u0e42\u0e23\u0e07  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 321 tt-03 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569127274\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e27\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e2d\u0e2a\u0e40\u0e17\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":6000000,\"capital_display\":\"6,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127274 \u0e1a\u0e08.\u0e41\u0e27\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e2d\u0e2a\u0e40\u0e17\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 6000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e1e\u0e23\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1805 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e43\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142851\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e41\u0e2d\u0e1e\u0e1e\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142851 \u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e41\u0e2d\u0e1e\u0e1e\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c (software) \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 (application) \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (digital platform) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1a\u0e1a\u0e02\u0e32\u0e22\u0e02\u0e32\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 (saas\/subscription) \u60c5\u5831\u901a\u4fe1\u30fbit 615\/26  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142869\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e25\u0e35\u0e48 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46633\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46633\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142869 \u0e1a\u0e08.\u0e08\u0e39\u0e25\u0e35\u0e48 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 46633 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e35 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 619\/223  \u0e16\u0e19\u0e19\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142907\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e48\u0e1a\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142907 \u0e1a\u0e08.\u0e42\u0e21\u0e48\u0e1a\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 64201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2b\u0e23\u0e37\u0e2d \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 39  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e19\u0e24\u0e21\u0e32\u0e13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143024\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143024 \u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/43  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143261\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e44\u0e25\u0e1f\u0e4c \u0e01\u0e32\u0e27\u0e32\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143261 \u0e1a\u0e08.\u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e44\u0e25\u0e1f\u0e4c \u0e01\u0e32\u0e27\u0e32\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 162  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 112(\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143342\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143342 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e22\u0e34\u0e21 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e19\u0e32\u0e21\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u82b8\u8853\u30fb\u5a2f\u697d 92\/50-52  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143440\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e42\u0e2d\u0e1e\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143440 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e42\u0e2d\u0e1e\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 64201 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e2b\u0e23\u0e37\u0e2d \u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 944  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e34\u0e15\u0e23\u0e1e\u0e32\u0e27\u0e19\u0e4c \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 525062 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025242\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e48\u0e32\u0e2b\u0e25\u0e07 \u0e2a\u0e15\u0e35\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025242 \u0e1a\u0e08.\u0e40\u0e1b\u0e48\u0e32\u0e2b\u0e25\u0e07 \u0e2a\u0e15\u0e35\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 1. \u0e17\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e30\u0e40\u0e02\u0e47\u0e1a\u0e15\u0e23\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e01\u0e4a\u0e32\u0e0b \u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e48\u0e2d\u0e01\u0e4a\u0e32\u0e0b \u0e17\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e30\u0e40\u0e02\u0e47\u0e1a\u0e15\u0e23\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e41\u0e19\u0e27\u0e15\u0e30\u0e40\u0e02\u0e47\u0e1a\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 2. \u0e17\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e14\u0e33\u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32\u0e17\u0e19\u0e41\u0e23\u0e07\u0e14\u0e36\u0e07\u0e2a\u0e39\u0e07 \u0e17\u0e23\u0e07\u0e01\u0e25\u0e21 \u0e17\u0e32\u0e07\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e15\u0e38\u0e23\u0e31\u0e2a \u0e17\u0e23\u0e07\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e1c\u0e37\u0e19\u0e1c\u0e49\u0e32 \u0e02\u0e19\u0e32\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 3. \u0e17\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e0a\u0e38\u0e1a\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35 \u0e17\u0e23\u0e07\u0e01\u0e25\u0e21 \u0e17\u0e23\u0e07\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e08\u0e15\u0e38\u0e23\u0e31\u0e2a \u0e17\u0e23\u0e07\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e48\u0e22\u0e21\u0e1c\u0e37\u0e19\u0e1c\u0e49\u0e32 \u0e02\u0e19\u0e32\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e31\u0e2d\u0e07\u0e01\u0e32\u0e23 4. \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13\u0e15\u0e31\u0e27\u0e0b\u0e35 \u0e21\u0e2d\u0e01. 5. \u0e17\u0e48\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e49\u0e2d\u0e22\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e0a\u0e19\u0e34\u0e14\u0e17\u0e48\u0e2d emt \u0e17\u0e48\u0e2d imc \u0e17\u0e48\u0e2d rsc 6. \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e25\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0165569001793\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e21\u0e07\u0e04\u0e25\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001793 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e21\u0e07\u0e04\u0e25\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 102\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039609\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e14\u0e35 \u0e27\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039609 \u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e14\u0e35 \u0e27\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27) \u5bbf\u6cca\u30fb\u98f2\u98df 99\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039668\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e34\u0e07-\u0e44\u0e2d\u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e23\u0e2d\u0e19\u0e40\u0e21\u0e19\u0e17\u0e31\u0e25 \u0e42\u0e1e\u0e23\u0e40\u0e17\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039668 \u0e1a\u0e08.\u0e40\u0e2b\u0e34\u0e07-\u0e44\u0e2d\u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e23\u0e2d\u0e19\u0e40\u0e21\u0e19\u0e17\u0e31\u0e25 \u0e42\u0e1e\u0e23\u0e40\u0e17\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 28299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e21\u0e25\u0e1e\u0e34\u0e29 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u88fd\u9020 9\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569010066\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e25\u0e2a\u0e40\u0e17\u0e19\u0e0b\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25939\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25939\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010066 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e25\u0e2a\u0e40\u0e17\u0e19\u0e0b\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 25939 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1c\u0e48\u0e19\u0e40\u0e08\u0e35\u0e22\u0e23 \/ \u0e41\u0e21\u0e48\u0e41\u0e1a\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e38\u0e1a\u0e1c\u0e34\u0e27\u0e2b\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19 \u88fd\u9020 569\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0335569001210\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e28\u0e23\u0e35\u0e40\u0e01\u0e29 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001210 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e28\u0e23\u0e35\u0e40\u0e01\u0e29 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 46313 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e1e\u0e47\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0395569000485\",\"name_th\":\"\u0e1a\u0e08.\u0e2d.\u0e23\u0e27\u0e21\u0e0a\u0e31\u0e22 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e25\u0e4a\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000485 \u0e1a\u0e08.\u0e2d.\u0e23\u0e27\u0e21\u0e0a\u0e31\u0e22 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e25\u0e4a\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 46695 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 249  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0415569004081\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e04\u0e25\u0e34\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004081 \u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e2a\u0e04\u0e25\u0e34\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e04\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 140\/133  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e16\u0e44\u0e1f \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0553569000457\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e48\u0e32\u0e25\u0e49\u0e2d \u0e2d\u0e35\u0e27\u0e35 \u0e2e\u0e31\u0e1a\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0553569000457 \u0e2b\u0e08.\u0e17\u0e48\u0e32\u0e25\u0e49\u0e2d \u0e2d\u0e35\u0e27\u0e35 \u0e2e\u0e31\u0e1a 2569-07-31 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 336  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0735569007702\",\"name_th\":\"\u0e1a\u0e08.\u0e15.\u0e40\u0e02\u0e47\u0e21\u0e17\u0e2d\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007702 \u0e1a\u0e08.\u0e15.\u0e40\u0e02\u0e47\u0e21\u0e17\u0e2d\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e14\u0e16\u0e19\u0e19 \u0e17\u0e33\u0e16\u0e19\u0e19\u0e25\u0e39\u0e01\u0e23\u0e31\u0e07 \u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e16\u0e19\u0e19\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e08\u0e23\u0e32\u0e08\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 210  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0803569001094\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001094 \u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-31 5000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569142621\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e0a\u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142621 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e0a\u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e1c\u0e49\u0e32 \u0e14\u0e49\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e41\u0e25\u0e30\u0e2b\u0e34\u0e19\u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 553\/288  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e23\u0e32\u0e0d\u0e2a\u0e34\u0e23\u0e34 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142681\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e34\u0e40\u0e04\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142681 \u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e34\u0e40\u0e04\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142702\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e17\u0e34\u0e2a \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142702 \u0e1a\u0e08.\u0e40\u0e21\u0e17\u0e34\u0e2a \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 1723\/60  \u0e16\u0e19\u0e19\u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025170\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e19\u0e32\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025170 \u0e1a\u0e08.\u0e2b\u0e19\u0e32\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e2d\u0e19\u0e49\u0e33\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e25\u0e21 \u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25 \u0e01\u0e4a\u0e32\u0e0a\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 (\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u5efa\u8a2d 599\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569039498\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e07\u0e1a\u0e32\u0e23\u0e4c \u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039498 \u0e1a\u0e08.\u0e2b\u0e25\u0e07\u0e1a\u0e32\u0e23\u0e4c \u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 74  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e1a\u0e21\u0e30\u0e22\u0e21 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0335569001198\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e30\u0e22\u0e30\u0e22\u0e19\u0e15\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001198 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e30\u0e22\u0e30\u0e22\u0e19\u0e15\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 45101 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0505569016878\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e32\u0e01\u0e49\u0e2d\u0e19\u0e40\u0e01\u0e15 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016878 \u0e1a\u0e08.\u0e14\u0e23\u0e32\u0e01\u0e49\u0e2d\u0e19\u0e40\u0e01\u0e15 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 68201 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e0d\u52d5\u7523 35\/1   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e482 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e48\u0e2d \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e48\u0e2d \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0745569008067\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e25\u0e32\u0e14 \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e40\u0e08\u0e32\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008067 \u0e1a\u0e08.\u0e09\u0e25\u0e32\u0e14 \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e40\u0e08\u0e32\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 43901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e40\u0e08\u0e32\u0e30 \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e44\u0e21\u0e42\u0e04\u0e23\u0e44\u0e1e\u0e25\u0e4c \u0e07\u0e32\u0e19\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e04\u0e2d\u0e19\u0e42\u0e14  \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e15\u0e2d\u0e01\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 51\/99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013906\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e44\u0e1f\u0e27\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013906 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e44\u0e1f\u0e27\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 5000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e31\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e1e\u0e32\u0e04\u0e19\u0e44\u0e17\u0e22\u0e44\u0e1b\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (outbound) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e39\u0e48\u0e04\u0e13\u0e30\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 98\/275  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569142451\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35 \u0e40\u0e07\u0e34\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142451 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35 \u0e40\u0e07\u0e34\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e1d\u0e32\u0e01 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 18-20  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 49 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0715569002867\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e25\u0e2d\u0e2d\u0e19 \u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002867 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e25\u0e2d\u0e2d\u0e19 \u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 5000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07 \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e02\u0e31\u0e14 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01 \u0e02\u0e31\u0e14\u0e40\u0e07\u0e32 \u0e14\u0e39\u0e14\u0e1d\u0e38\u0e48\u0e19 \u0e0b\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e30 \u0e0b\u0e31\u0e01\u0e1e\u0e23\u0e21 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e49\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039391\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e40\u0e08\u0e34\u0e22\u0e2b\u0e22\u0e39 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039391 \u0e1a\u0e08.\u0e0b\u0e34\u0e40\u0e08\u0e34\u0e22\u0e2b\u0e22\u0e39 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 5000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 119\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0835569013884\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e19\u0e15\u0e4c \u0e1a\u0e25\u0e39 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013884 \u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e19\u0e15\u0e4c \u0e1a\u0e25\u0e39 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19  \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u5efa\u8a2d 74\/57  \u0e16\u0e19\u0e19\u0e1e\u0e39\u0e19\u0e1c\u0e25 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569141340\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e1b\u0e35\u0e22\u0e19\u0e2a\u0e4c \u0e21\u0e32\u0e14\u0e34\u0e0b\u0e39\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141340 \u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e1b\u0e35\u0e22\u0e19\u0e2a\u0e4c \u0e21\u0e32\u0e14\u0e34\u0e0b\u0e39\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e40\u0e1b\u0e35\u0e22\u0e19\u0e2a\u0e4c \u0e21\u0e32\u0e14\u0e34\u0e0b\u0e39\u0e2a \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 3 (\u0e2a\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07) \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141463\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e47\u0e2d\u0e1b \u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e04\u0e04\u0e2d\u0e42\u0e19\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141463 \u0e1a\u0e08.\u0e0a\u0e47\u0e2d\u0e1b \u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e04\u0e04\u0e2d\u0e42\u0e19\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 3c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 989   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1228 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12a \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e481 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141544\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32 \u0e42\u0e16\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141544 \u0e1a\u0e08.\u0e2d\u0e32 \u0e42\u0e16\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e23\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46  \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u88fd\u9020 28   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e40\u0e2d4\/9 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e04\u0e40\u0e1a\u0e25\u0e25\u0e4c \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e1a \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141561 \u0e1a\u0e08.\u0e40\u0e17\u0e04\u0e40\u0e1a\u0e25\u0e25\u0e4c \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e1a \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e25\u0e21\u0e41\u0e2b\u0e49\u0e07 \u0e15\u0e31\u0e27\u0e01\u0e23\u0e2d\u0e07\u0e25\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141692\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e0a\u0e1a\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141692 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e0a\u0e1a\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e0d\u52d5\u7523 10\/44  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141935\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e19\u0e17\u0e34\u0e0a\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141935 \u0e1a\u0e08.\u0e19\u0e19\u0e17\u0e34\u0e0a\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e33 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u4e0d\u52d5\u7523 306\/1  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e3212 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142109\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2b\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e19\u0e32\u0e22\u0e40\u0e01\u0e48\u0e07\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142109 \u0e1a\u0e08.\u0e44\u0e2b\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e19\u0e32\u0e22\u0e40\u0e01\u0e48\u0e07\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 (\u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c) \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/99  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028136\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e08\u0e34\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028136 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e08\u0e34\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 55101 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21 \u0e41\u0e1a\u0e1a\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e17\u0e31\u0e49\u0e07\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e43\u0e01\u0e25\u0e49\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 75\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028209\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028209 \u0e1a\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 43210 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c ev \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u5efa\u8a2d 44\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039234\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e40\u0e2b\u0e21\u0e48\u0e22 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039234 \u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e40\u0e2b\u0e21\u0e48\u0e22 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 306\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039242\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e30 \u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19 \u0e23\u0e35\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039242 \u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e30 \u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19 \u0e23\u0e35\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 78300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e21\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 287\/171  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039251\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e40\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25921\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25921\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039251 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e40\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 25921 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1e\u0e48\u0e19 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e42\u0e25\u0e2b\u0e30 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 215  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e40\u0e01\u0e32\u0e30\u0e42\u0e1e\u0e18\u0e34\u0e4c - \u0e2a\u0e32\u0e21\u0e41\u0e22\u0e01 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569004066\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e19\u0e42\u0e1f\u0e23 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86102\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86102\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004066 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e19\u0e42\u0e1f\u0e23 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 86102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e44\u0e15\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e15\u0e27\u0e32\u0e22\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 \u533b\u7642\u30fb\u798f\u7949 959\/8  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002187\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e13\u0e31\u0e10\u0e23\u0e38\u0e17\u0e18\u0e34\u0e4c \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002187 \u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e13\u0e31\u0e10\u0e23\u0e38\u0e17\u0e18\u0e34\u0e4c \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e15\u0e32\u0e21\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e27\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\/\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e41\u0e25\u0e30\u0e02\u0e38\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e2b\u0e0d\u0e48 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\/\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0275569001199\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e44\u0e0a\u0e22\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001199 \u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e44\u0e0a\u0e22\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e15\u0e32\u0e21\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e27\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\/\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e41\u0e25\u0e30\u0e02\u0e38\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e2b\u0e0d\u0e48 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\/\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002974\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 2026\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002974 \u0e2b\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 2026 2569-07-27 5000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e33\u0e23\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 144\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0345569003441\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e15\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003441 \u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e15\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 390  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0405569007292\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"61209\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"61209\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007292 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 61209 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35 \u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19(mobile virtual network operator: mvno) \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e42\u0e14\u0e22\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e0a\u0e48\u0e32\u0e43\u0e0a\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e23\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e02\u0e2d\u0e07\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 345\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0445569001782\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e2a\u0e01\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001782 \u0e1a\u0e08.\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e2a\u0e01\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u533b\u7642\u30fb\u798f\u7949 82  \u0e16\u0e19\u0e19\u0e16\u0e35\u0e19\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0505569016746\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e18\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 208 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016746 \u0e1a\u0e08.\u0e1e\u0e35 \u0e18\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 208 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 123\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016762\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e27\u0e34\u0e23\u0e34\u0e22\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55901\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55901\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016762 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e27\u0e34\u0e23\u0e34\u0e22\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 55901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0715569002841\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002841 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 - \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e23\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002859\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e25\u0e32\u0e2a\u0e15\u0e4c \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24102\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24102\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002859 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e25\u0e32\u0e2a\u0e15\u0e4c \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 24102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e02\u0e31\u0e14\u0e42\u0e25\u0e2b\u0e30 \u0e42\u0e14\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e21\u0e47\u0e14\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e21\u0e47\u0e14\u0e2b\u0e22\u0e32\u0e1a\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e21\u0e47\u0e14\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e25\u0e27\u0e14\u0e15\u0e31\u0e14\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e40\u0e21\u0e47\u0e14\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u88fd\u9020 11\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007621\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007621 \u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21  \u0e2b\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e42\u0e14\u0e22\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 496\/76  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e23\u0e23\u0e04\u0e32 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569008008\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e27\u0e34\u0e19 \u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008008 \u0e1a\u0e08.\u0e40\u0e2b\u0e27\u0e34\u0e19 \u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07  \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 112\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0805569002955\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002955 \u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e22\u0e37\u0e21 \u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19\u0e41\u0e01\u0e48 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e42\u0e14\u0e22\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d \u0e21\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e1a\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e33\u0e19\u0e33\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e40\u0e07\u0e34\u0e19\u0e01\u0e39\u0e49\u0e41\u0e25\u0e30\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e0b\u0e36\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e04\u0e48\u0e32\u0e1b\u0e23\u0e31\u0e1a \u0e04\u0e48\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a \u0e2d\u0e2d\u0e01\u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e15\u0e31\u0e4b\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e37\u0e48\u0e22\u0e19\u0e21\u0e37\u0e2d\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 8  \u0e0b\u0e2d\u0e22 \u0e2b\u0e2d\u0e44\u0e15\u0e23 3 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e04\u0e39\u0e02\u0e27\u0e32\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0135569023177\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e2a\u0e1e\u0e42\u0e0a\u0e04 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31009\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31009\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023177 \u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e2a\u0e1e\u0e42\u0e0a\u0e04 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 5000000 31009 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e1f\u0e32 \u0e1a\u0e34\u0e27\u0e17\u0e4c\u0e2d\u0e34\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 95\/175  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e42\u0e2d \u0e1a\u0e25\u0e34\u0e2a\u0e0b\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023185\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023185 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 95\/175  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e42\u0e2d \u0e1a\u0e25\u0e34\u0e2a\u0e0b\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023193\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e32\u0e16\u0e48\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023193 \u0e1a\u0e08.\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e32\u0e16\u0e48\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 95\/175  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e42\u0e2d \u0e1a\u0e25\u0e34\u0e2a\u0e0b\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023207\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e49\u0e2d\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023207 \u0e1a\u0e08.\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e49\u0e2d\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 95\/175  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e42\u0e2d \u0e1a\u0e25\u0e34\u0e2a\u0e0b\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569141056\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e25 \u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141056 \u0e1a\u0e08.\u0e42\u0e1f\u0e25 \u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 9  \u0e0b\u0e2d\u0e22 \u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 4 \u0e0b\u0e2d\u0e22 84 \u0e41\u0e22\u0e01 2-8 \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141099\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141099 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 68201 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u4e0d\u52d5\u7523 144\/25  \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141188\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e01\u0e34 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141188 \u0e1a\u0e08.\u0e42\u0e17\u0e01\u0e34 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 3  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141218\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04 \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141218 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04 \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u5efa\u8a2d 61\/659  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141234\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e23\u0e2a\u0e4c\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141234 \u0e1a\u0e08.\u0e44\u0e23\u0e2a\u0e4c\u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u88fd\u9020 8\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141242\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e07\u0e44\u0e17\u0e48 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e49\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141242 \u0e1a\u0e08.\u0e15\u0e49\u0e07\u0e44\u0e17\u0e48 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e49\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1e\u0e37\u0e49\u0e19 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1e\u0e37\u0e49\u0e19  \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1e\u0e37\u0e49\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e1e\u0e37\u0e49\u0e19\u0e01\u0e31\u0e19\u0e0b\u0e36\u0e21  \u0e14\u0e32\u0e14\u0e1f\u0e49\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e34 3d \u0e1e\u0e37\u0e49\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e16\u0e19\u0e19\u0e01\u0e31\u0e19\u0e25\u0e37\u0e48\u0e19 \u0e1e\u0e37\u0e49\u0e19 epoxy (\u0e2d\u0e35\u0e1e\u0e47\u0e2d\u0e01\u0e0b\u0e35\u0e48) \u0e1e\u0e37\u0e49\u0e19 epoxy-self-leveling,epoxy coating, \u0e1e\u0e37\u0e49\u0e19 pu (\u0e1e\u0e35\u0e22\u0e39)  \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 123\/84  \u0e16\u0e19\u0e19\u0e09\u0e25\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569023126\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023126 \u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u4e0d\u52d5\u7523 55\/55   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 55 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023134\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023134 \u0e1a\u0e08.\u0e0a\u0e31\u0e22 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u5efa\u8a2d 43\/96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0255569002161\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35 \u0e0a\u0e47\u0e2d\u0e1b 1986  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002161 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35 \u0e0a\u0e47\u0e2d\u0e1b 1986  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e34\u0e27\u0e01\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e14\u0e31\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e41\u0e2d\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c ( \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 ) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003405\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e25\u0e34\u0e15 \u0e42\u0e04\u0e42\u0e04\u0e48\u0e40\u0e1f\u0e23\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003405 \u0e1a\u0e08.\u0e25\u0e34\u0e25\u0e34\u0e15 \u0e42\u0e04\u0e42\u0e04\u0e48\u0e40\u0e1f\u0e23\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 5000000 10309 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e19\u0e49\u0e33\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u88fd\u9020 160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0103569008036\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e13\u0e22\u0e32 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47511\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47511\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008036 \u0e2b\u0e08.\u0e1a\u0e38\u0e13\u0e22\u0e32 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-24 5000000 47511 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/506   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 174 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139671\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e40\u0e27\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139671 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e40\u0e27\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 981   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 23, 24, 25, 18b, 19b \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139868\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e15\u0e34\u0e40\u0e21\u0e17 \u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139868 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e15\u0e34\u0e40\u0e21\u0e17 \u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 864\/50  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e43\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139957\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139957 \u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 39  \u0e0b\u0e2d\u0e22 \u0e40\u0e01\u0e29\u0e21\u0e2a\u0e31\u0e19\u0e15\u0e4c 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140068\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140068 \u0e1a\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e08\u0e31\u0e01\u0e23\u0e40\u0e22\u0e47\u0e1a\u0e1c\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e40\u0e0a\u0e48\u0e19 \u0e1c\u0e49\u0e32 \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e14\u0e38\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122\/1  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140165\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e1a\u0e2d\u0e23\u0e4c\u0e19 \u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140165 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e1a\u0e2d\u0e23\u0e4c\u0e19 \u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e22\u0e48\u0e2d\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a (\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e42\u0e01\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u91d1\u878d\u30fb\u4fdd\u967a 15  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e08\u0e39\u0e23\u0e35\u0e48 \u0e40\u0e14\u0e2d\u0e30\u0e21\u0e39\u0e1f\u0e27\u0e35\u0e48 \u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s-03 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140203\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140203 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a  \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32  \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1788  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1404 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 14 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140327\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e19\u0e34\u0e27\u0e17\u0e23\u0e31\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e42\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140327 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e19\u0e34\u0e27\u0e17\u0e23\u0e31\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e42\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e2d\u0e2d\u0e01\u0e1a\u0e39\u0e18\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 129  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1506 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 15 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140351\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140351 \u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e42\u0e14\u0e22\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e1a\u0e01 (freight forwatder) \u904b\u8f38\u30fb\u7269\u6d41 818  \u0e0b\u0e2d\u0e22 \u0e0a\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140394\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140394 \u0e1a\u0e08.\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 45\/78  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 57 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140416\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140416 \u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 524  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e1427 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140441\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e25\u0e25\u0e34\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140441 \u0e1a\u0e08.\u0e21\u0e31\u0e25\u0e25\u0e34\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 55\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140459\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e25\u0e34\u0e19 \u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140459 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e25\u0e34\u0e19 \u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/63  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 24 (\u0e21.\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140483\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140483 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 106\/83  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140599\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140599 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299\/2  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01  24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140777\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e21\u0e25\u0e27\u0e23\u0e23\u0e13 \u0e2a\u0e1b\u0e2d\u0e15\u0e23\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140777 \u0e1a\u0e08.\u0e01\u0e21\u0e25\u0e27\u0e23\u0e23\u0e13 \u0e2a\u0e1b\u0e2d\u0e15\u0e23\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e2b\u0e34\u0e49\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140785\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e35\u0e42\u0e23\u0e48 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140785 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e35\u0e42\u0e23\u0e48 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07  (advanced materials) \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1c\u0e2a\u0e21 (composite materials) \u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27\u0e0b\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 719\/63  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2762 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140874\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e39\u0e19\u0e14\u0e32\u0e23\u0e35\u0e48 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140874 \u0e1a\u0e08.\u0e1a\u0e39\u0e19\u0e14\u0e32\u0e23\u0e35\u0e48 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c 111 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140947\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e23\u0e34 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140947 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e23\u0e34 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 68201 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u4e0d\u52d5\u7523 135\/9  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 63 (\u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e19\u0e15\u0e4c3) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024530\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e21\u0e32\u0e27\u0e34\u0e19 \u0e25\u0e2d\u0e27\u0e4c\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024530 \u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e21\u0e32\u0e27\u0e34\u0e19 \u0e25\u0e2d\u0e27\u0e4c\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35 \u0e2a\u0e37\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35 \u0e40\u0e40\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e27\u0e07\u0e16\u0e32\u0e21\u0e2b\u0e19\u0e35\u0e49 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 959\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024581\",\"name_th\":\"\u0e1a\u0e08.\u0e1c\u0e39\u0e48\u0e40\u0e16\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024581 \u0e1a\u0e08.\u0e1c\u0e39\u0e48\u0e40\u0e16\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 599\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024696\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e1e\u0e35\u0e40\u0e1e\u0e34\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024696 \u0e1a\u0e08.\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e1e\u0e35\u0e40\u0e1e\u0e34\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2122\/11-15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024718\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35-\u0e0b\u0e35\u0e27\u0e32\u0e22 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024718 \u0e1a\u0e08.\u0e17\u0e35-\u0e0b\u0e35\u0e27\u0e32\u0e22 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 242\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0165569001751\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e2d\u0e1e\u0e2d\u0e2a \u0e42\u0e1e\u0e25\u0e17\u0e23\u0e35\u0e48 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01462\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01462\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001751 \u0e1a\u0e08.\u0e2b\u0e21\u0e2d\u0e1e\u0e2d\u0e2a \u0e42\u0e1e\u0e25\u0e17\u0e23\u0e35\u0e48 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 01462 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48 \u8fb2\u6797\u6c34\u7523 93\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038823\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e07\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e40\u0e2d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038823 \u0e1a\u0e08.\u0e41\u0e0b\u0e07\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e40\u0e2d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 168\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038921\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038921 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 336\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038947\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35. \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e2a\u0e4c\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038947 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35. \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e2a\u0e4c\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 109\/27-109\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038955\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35. \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e2a\u0e4c\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038955 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35. \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e2a\u0e4c\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 109\/27-109\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009840\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32 \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009840 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32 \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 156\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0255569002152\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002152 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0405569007179\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56303\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56303\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007179 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f  \u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 333  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007209\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e41\u0e27\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e14\u0e34\u0e2a\u0e17\u0e23\u0e34\u0e1a\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007209 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e41\u0e27\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e14\u0e34\u0e2a\u0e17\u0e23\u0e34\u0e1a\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007217\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007217 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 643\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003963\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e0a\u0e47\u0e04\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003963 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e0a\u0e47\u0e04\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 752  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e31\u0e01\u0e29\u0e4c4 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016631\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016631 \u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e23\u0e34\u0e21\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e28\u0e29\u0e40\u0e07\u0e34\u0e19,\u0e17\u0e2d\u0e07 \u0e40\u0e28\u0e29\u0e17\u0e2d\u0e07,\u0e40\u0e1e\u0e0a\u0e23 \u0e40\u0e28\u0e29\u0e40\u0e1e\u0e0a\u0e23,\u0e1e\u0e25\u0e2d\u0e22 \u0e40\u0e28\u0e29\u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 259\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0605569002205\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e49\u0e01-\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10802\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10802\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002205 \u0e1a\u0e08.\u0e40\u0e2d\u0e49\u0e01-\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 10802 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e1b\u0e39\u0e48\u0e22\u0e48\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e44\u0e01\u0e48\u0e1e\u0e48\u0e2d\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e21\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e23\u0e07\u0e1f\u0e31\u0e01\u0e44\u0e02\u0e48 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e02\u0e48\u0e1f\u0e31\u0e01\u0e21\u0e35\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e25\u0e39\u0e01\u0e44\u0e01\u0e48 \u0e44\u0e01\u0e48\u0e2a\u0e32\u0e27 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u88fd\u9020 288\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0635569001501\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e38\u0e14\u0e32113 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001501 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e38\u0e14\u0e32113 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002400\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e0a\u0e32\u0e14\u0e32 \u0e21\u0e2b\u0e32\u0e40\u0e2e\u0e07 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002400 \u0e1a\u0e08.\u0e2a\u0e38\u0e0a\u0e32\u0e14\u0e32 \u0e21\u0e2b\u0e32\u0e40\u0e2e\u0e07 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 327\/3  \u0e16\u0e19\u0e19\u0e44\u0e0a\u0e22\u0e32\u0e19\u0e38\u0e20\u0e32\u0e1e \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0673569000545\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e31\u0e2a\u0e14\u0e38\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0673569000545 \u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e31\u0e2a\u0e14\u0e38 2569-07-24 5000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0675569001586\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001586 \u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 156\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0735569007516\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e17\u0e35\u0e40\u0e2d\u0e0a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007516 \u0e1a\u0e08.\u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e17\u0e35\u0e40\u0e2d\u0e0a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e31\u0e1a\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 (energy storage systems) \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 555\/80  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007974\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e23\u0e2d\u0e19 \u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007974 \u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e23\u0e2d\u0e19 \u0e42\u0e1e\u0e25\u0e34\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013698\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e34\u0e25\u0e25\u0e34\u0e42\u0e2d \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013698 \u0e1a\u0e08.\u0e01\u0e23\u0e34\u0e25\u0e25\u0e34\u0e42\u0e2d \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 59\/414  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013761\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013761 \u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e1c\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e1b\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/16  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0f\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 200\u0e1b\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0905569006143\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006143 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46443 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 127\/294  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006151\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e15\u0e42\u0e15\u0e2e\u0e31\u0e1a \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006151 \u0e1a\u0e08.\u0e25\u0e2d\u0e15\u0e42\u0e15\u0e2e\u0e31\u0e1a \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 127\/294  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006160\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006160 \u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 46443 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27  \u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006186\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006186 \u0e1a\u0e08.\u0e2d\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e19\u0e33\u0e21\u0e32\u0e08\u0e31\u0e14\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e48\u0e2d\u0e22 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e14 \u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e1c\u0e07\u0e04\u0e49\u0e32 \u4e0d\u52d5\u7523 888\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e19\u0e34\u0e0a \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006224\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e14\u0e32 \u0e01\u0e34\u0e1f\u0e15\u0e4c \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006224 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e14\u0e32 \u0e01\u0e34\u0e1f\u0e15\u0e4c \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 335  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569138781\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138781 \u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e07\u0e34\u0e19 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e44\u0e02\u0e48\u0e21\u0e38\u0e01 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e1e\u0e25\u0e15\u0e17\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e42\u0e25\u0e2b\u0e30 \u0e42\u0e25\u0e2b\u0e30\u0e1c\u0e2a\u0e21 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 96\/47  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138861\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2d\u0e25 \u0e2d\u0e40\u0e25\u0e18\u0e2d\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138861 \u0e1a\u0e08.\u0e1e\u0e2d\u0e25 \u0e2d\u0e40\u0e25\u0e18\u0e2d\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e43\u0e14 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1467\/8  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30\u0e44\u0e23\u0e0b\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12\u0e40\u0e2d \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138888\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2d\u0e19\u0e17\u0e32\u0e23\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138888 \u0e1a\u0e08.\u0e21\u0e2d\u0e19\u0e17\u0e32\u0e23\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 3  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138942\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e40\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138942 \u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e40\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/54  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139035\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e14\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139035 \u0e1a\u0e08.\u0e42\u0e01\u0e14\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 144\/69  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139094\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e15\u0e23\u0e15\u0e34\u0e07 \u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139094 \u0e1a\u0e08.\u0e21\u0e34\u0e15\u0e23\u0e15\u0e34\u0e07 \u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u0e25\u0e30\u0e04\u0e23 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e01\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d (mv) \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1c\u0e25\u0e07\u0e32\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 151\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139477\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e42\u0e01 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139477 \u0e1a\u0e08.\u0e44\u0e14\u0e42\u0e01 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e41\u0e23\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 919\/223  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e34\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e40\u0e17\u0e23\u0e14 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139558\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e19\u0e32\u0e02\u0e27\u0e31\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139558 \u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e19\u0e32\u0e02\u0e27\u0e31\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e27\u0e19 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e27\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 3738\/159 \u0e15\u0e23\u0e2d\u0e01\u0e19\u0e2d\u0e01\u0e40\u0e02\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024335\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e40\u0e19\u0e2d\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024335 \u0e1a\u0e08.\u0e40\u0e1a\u0e40\u0e19\u0e2d\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e1c\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1b\u0e25\u0e07\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 (inverter) \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 (mounting system)  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e15\u0e39\u0e49\u0e44\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07 \u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569022758\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07 \u0e2d\u0e2d\u0e1f \u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022758 \u0e1a\u0e08.\u0e04\u0e34\u0e07 \u0e2d\u0e2d\u0e1f \u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/247  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022766\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e21\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022766 \u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e21\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 20299 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e19\u0e49\u0e33\u0e22\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e2a\u0e21\u0e2a\u0e35 \u88fd\u9020 7\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569038769\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e22\u0e2d\u0e19 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038769 \u0e1a\u0e08.\u0e17\u0e22\u0e2d\u0e19 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 285\/748  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038777\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c\u0e42\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038777 \u0e1a\u0e08.\u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c\u0e42\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e32\u0e23\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e49\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 378\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038785\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47892\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47892\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038785 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 47892 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 136\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009807\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e19\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009807 \u0e1a\u0e08.\u0e17\u0e39\u0e19\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e42\u0e2d\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 402\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002331\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19\u0e42\u0e1b\u0e23 \u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002331 \u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19\u0e42\u0e1b\u0e23 \u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 44\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0315569001988\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e38\u0e15\u0e34\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01462\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01462\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001988 \u0e1a\u0e08.\u0e0a\u0e38\u0e15\u0e34\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 01462 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48 \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e04\u0e2d\u0e01\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48 \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u8fb2\u6797\u6c34\u7523 131\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0325569001261\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001261 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u5efa\u8a2d 69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0415569003939\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003939 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e42\u0e15\u0e4a\u0e30 \u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07 \u0e41\u0e08\u0e01\u0e31\u0e19 \u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e39\u0e1b \u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32\u0e41\u0e02\u0e27\u0e19\u0e1c\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e21\u0e34\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 324  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0425569000573\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e42\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000573 \u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e42\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e08\u0e31\u0e14\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e41\u0e08\u0e01\u0e31\u0e19 \u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e39\u0e1b \u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0543569000295\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e28\u0e23\u0e35\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e39\u0e48\u0e17\u0e2d\u0e07\u0e40\u0e14\u0e48\u0e19\u0e0a\u0e31\u0e22\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0543569000295 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e28\u0e23\u0e35\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e39\u0e48\u0e17\u0e2d\u0e07\u0e40\u0e14\u0e48\u0e19\u0e0a\u0e31\u0e22 2569-07-23 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 38\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0653569001207\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001207 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 2569-07-23 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e30 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u5efa\u8a2d 909\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0675569001560\",\"name_th\":\"\u0e1a\u0e08.13 \u0e2a\u0e40\u0e1b\u0e01\u0e15\u0e23\u0e31\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001560 \u0e1a\u0e08.13 \u0e2a\u0e40\u0e1b\u0e01\u0e15\u0e23\u0e31\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35-\u0e2b\u0e25\u0e48\u0e21\u0e2a\u0e31\u0e01 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0735569007478\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01121\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01121\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007478 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 01121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28          \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14       (2)\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e17\u0e31\u0e49\u0e07\u0e25\u0e33 \u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d           \u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e32\u0e21\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28       (3) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28       (4)\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e20\u0e32\u0e04\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19           \u0e42\u0e23\u0e07\u0e1e\u0e31\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19       (5) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e34 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u8fb2\u6797\u6c34\u7523 65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0965569000561\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e23\u0e32\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0965569000561 \u0e1a\u0e08.\u0e19\u0e23\u0e32\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 5000000 46109 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 291  \u0e16\u0e19\u0e19\u0e23\u0e30\u0e41\u0e07\u0e30\u0e21\u0e23\u0e23\u0e04\u0e32 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569138071\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e2d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138071 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e2d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 11\/2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138144\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e27\u0e32\u0e22 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138144 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e27\u0e32\u0e22 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 46206 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e47\u0e17\u0e0a\u0e47\u0e2d\u0e1b \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 641\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138161\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138161 \u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e25\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 102\/1  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c-\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138420\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138420 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 85  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1914 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024149\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e35\u0e22\u0e39 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024149 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e35\u0e22\u0e39 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (electric vehicle charger \u0e2b\u0e23\u0e37\u0e2d ev charger) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e2a\u0e25\u0e31\u0e1a (ac charger) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e15\u0e23\u0e07 (dc fast charger) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e47\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e2b\u0e31\u0e27\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e2a\u0e32\u0e22\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e15\u0e39\u0e49\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 69\/328  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 pleno \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17-\u0e1a\u0e32\u0e07\u0e19\u0e32 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024246\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e32\u0e1a\u0e14\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024246 \u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e32\u0e1a\u0e14\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e33 \u4e0d\u52d5\u7523 335  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e01\u0e21.19 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024254\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024254 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e33 \u4e0d\u52d5\u7523 335  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e01\u0e21.19 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027580\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027580 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/195  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022693\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1a\u0e22\u0e34\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022693 \u0e1a\u0e08.\u0e42\u0e1a\u0e22\u0e34\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 49334 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 88\/888  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0165569001688\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e25\u0e39\u0e22\u0e2d\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001688 \u0e1a\u0e08.\u0e2d\u0e25\u0e39\u0e22\u0e2d\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001696\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d 789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001696 \u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d 789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038351\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e34\u0e19\u0e01\u0e35\u0e49\u0e04\u0e2d\u0e19 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038351 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e34\u0e19\u0e01\u0e35\u0e49\u0e04\u0e2d\u0e19 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e31\u0e27\u0e40\u0e01\u0e47\u0e1a\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e04\u0e21\u0e35 (electrolytic capacitors) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 313\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038491\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e4c 89 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038491 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e4c 89 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 45102 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e23\u0e16\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e04\u0e25\u0e31\u0e1a\u0e04\u0e32\u0e23\u0e4c \u0e15\u0e39\u0e49\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e1f ev \u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038505\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e17\u0e34\u0e44\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038505 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e17\u0e34\u0e44\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 20121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 26\/24   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 26\/24 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003965\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e13\u0e35\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003965 \u0e1a\u0e08.\u0e21\u0e13\u0e35\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e25\u0e32\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u4e0d\u52d5\u7523 333\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002101\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e1e\u0e35. \u0e1f\u0e39\u0e49\u0e14 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002101 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e1e\u0e35. \u0e1f\u0e39\u0e49\u0e14 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e04\u0e23\u0e31\u0e27 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e40\u0e19\u0e49\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e1f\u0e39\u0e49\u0e14\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007595\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e1e\u0e34\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007595 \u0e1a\u0e08.\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e1e\u0e34\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e1a\u0e1c\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 296  \u0e16\u0e19\u0e19\u0e19\u0e34\u0e40\u0e27\u0e28\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0375569000400\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0375569000400 \u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e22\u0e48\u0e2d\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a (\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e42\u0e01\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e42\u0e01\u0e1e\u0e25\u0e31\u0e2a ) (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u91d1\u878d\u30fb\u4fdd\u967a 165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0385569000523\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e0a\u0e32\u0e23\u0e4c\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000523 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e0a\u0e32\u0e23\u0e4c\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e23\u0e49\u0e32\u0e19\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e27\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007021\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e24\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007021 \u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e24\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e27\u0e2d\u0e25\u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e42\u0e04\u0e21\u0e44\u0e1f \u0e41\u0e08\u0e01\u0e31\u0e19 \u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32\u0e15\u0e34\u0e14\u0e1c\u0e19\u0e31\u0e07 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32\u0e15\u0e31\u0e49\u0e07\u0e42\u0e15\u0e4a\u0e30 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e15\u0e48\u0e32\u0e07 \u0e46\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a \u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u0e40\u0e1b\u0e47\u0e19 \\\"\u0e17\u0e34\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545\\\" \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003882\",\"name_th\":\"\u0e1a\u0e08.\u0e2a77.\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003882 \u0e1a\u0e08.\u0e2a77.\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e38\u0e14\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07 \u0e2a\u0e15\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1e\u0e23\u0e21\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1c\u0e49\u0e32\u0e04\u0e25\u0e38\u0e21\u0e23\u0e16 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e15\u0e34\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e35\u0e48\u0e27\u0e32\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/5  \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003891\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003891 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e38\u0e14\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07 \u0e2a\u0e15\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 272  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003904\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e34\u0e29\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003904 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e34\u0e29\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e20\u0e32\u0e0a\u0e19\u0e30\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e2d\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e21\u0e34\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/5  \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0425569000557\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39\u0e17\u0e35 \u0e42\u0e25\u0e04\u0e31\u0e25 \u0e40\u0e17\u0e23\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000557 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39\u0e17\u0e35 \u0e42\u0e25\u0e04\u0e31\u0e25 \u0e40\u0e17\u0e23\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e1d\u0e32\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e02\u0e19\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01  \u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0485569000972\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000972 \u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u88fd\u9020 1  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e27\u0e14\u0e35 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21-\u0e17\u0e48\u0e32\u0e2d\u0e38\u0e40\u0e17\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0495569000573\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e14\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000573 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e14\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 108  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e33\u0e1c\u0e31\u0e01\u0e2b\u0e19\u0e2d\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001437\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e31\u0e25\u0e22\u0e32\u0e2b\u0e49\u0e32\u0e07\u0e09\u0e31\u0e15\u0e23 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e42\u0e01\u0e49\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52109\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52109\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0523569001437 \u0e2b\u0e08.\u0e01\u0e31\u0e25\u0e22\u0e32\u0e2b\u0e49\u0e32\u0e07\u0e09\u0e31\u0e15\u0e23 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e42\u0e01\u0e49 2569-07-22 5000000 52109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e14\u0e34\u0e1a \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27\u0e1a\u0e14 \u0e01\u0e32\u0e01\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e01\u0e32\u0e41\u0e1f\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002174\",\"name_th\":\"\u0e1a\u0e08.\u0e2d.\u0e17\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e2d\u0e30\u0e01\u0e23\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002174 \u0e1a\u0e08.\u0e2d.\u0e17\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e2d\u0e30\u0e01\u0e23\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 46530 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007435\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007435 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 46206 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e38\u0e19\u0e31\u0e02 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e21\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e02\u0e19\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/268  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007753\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1e\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007753 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1e\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 22220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e1f\u0e2d\u0e22\u0e25\u0e4c \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 288\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0803569001078\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e21\u0e48\u0e1c\u0e34\u0e27 \u0e2a\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e38\u0e15\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001078 \u0e2b\u0e08.\u0e41\u0e21\u0e48\u0e1c\u0e34\u0e27 \u0e2a\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e38\u0e15 2569-07-22 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002831\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e15\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002831 \u0e1a\u0e08.\u0e19\u0e31\u0e15\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 159\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002840\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002840 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e22\u0e32\u0e07\u0e41\u0e2d\u0e2a\u0e1f\u0e31\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e01\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 129\/672  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013515\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e2d\u0e2a \u0e44\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013515 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e2d\u0e2a \u0e44\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 60\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010664\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e2a\u0e4c\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010664 \u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e2a\u0e4c\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 5\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569006003\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35\u0e40\u0e04 \u0e2a\u0e42\u0e25\u0e1b\u0e42\u0e1e\u0e23\u0e40\u0e17\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006003 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35\u0e40\u0e04 \u0e2a\u0e42\u0e25\u0e1b\u0e42\u0e1e\u0e23\u0e40\u0e17\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e01\u0e31\u0e19\u0e14\u0e34\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e14\u0e34\u0e19\u0e2a\u0e44\u0e25\u0e14\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e08\u0e32\u0e30\u0e20\u0e39\u0e40\u0e02\u0e32 \u5efa\u8a2d 186\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007838\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007838 \u0e2b\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 2569-07-21 5000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/506   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 174 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007846\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1a\u0e2a\u0e17\u0e34\u0e14\u0e32 \u0e40\u0e14\u0e2d \u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e04\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007846 \u0e2b\u0e08.\u0e40\u0e1a\u0e2a\u0e17\u0e34\u0e14\u0e32 \u0e40\u0e14\u0e2d \u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e04 2569-07-21 5000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/506   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 174 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136907\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c \u0e27\u0e31\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136907 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c \u0e27\u0e31\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 45302 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 484  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 46 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136915\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136915 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46699 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e2b\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 484  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 46 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137032\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e20\u0e04\u0e32\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 1969 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10712\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10712\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137032 \u0e1a\u0e08.\u0e42\u0e20\u0e04\u0e32\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 1969 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 10712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 17  \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e41\u0e22\u0e01 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137059\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e21\u0e32\u0e23\u0e34\u0e0b\u0e48\u0e32 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137059 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e21\u0e32\u0e23\u0e34\u0e0b\u0e48\u0e32 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e25\u0e14\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 18\/57  \u0e16\u0e19\u0e19\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137156\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e27\u0e35 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137156 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e27\u0e35 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 64201 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 5073\/10  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137318\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e44\u0e1f\u0e19\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63120\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63120\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137318 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e44\u0e1f\u0e19\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 63120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e27\u0e47\u0e1a\u0e1e\u0e2d\u0e23\u0e4c\u0e17\u0e31\u0e25 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32 \u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 99\/34  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137377\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e01\u0e39\u0e4b\u0e0b\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137377 \u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e01\u0e39\u0e4b\u0e0b\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 52292 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e02\u0e2d\u0e07\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 15  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e08\u0e39\u0e23\u0e35\u0e48 \u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e39\u0e1f\u0e27\u0e35\u0e48 \u0e1e\u0e25\u0e48\u0e32\u0e0b\u0e48\u0e32 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137482\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e19\u0e40\u0e22\u0e27\u0e48 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137482 \u0e1a\u0e08.\u0e04\u0e38\u0e19\u0e40\u0e22\u0e27\u0e48 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e42\u0e25\u0e2b\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/71  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137571\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137571 \u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/3  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137628\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e42\u0e2e \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137628 \u0e1a\u0e08.\u0e40\u0e0b\u0e42\u0e2e \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u4e0d\u52d5\u7523 3  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137636\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e0a\u0e47\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137636 \u0e1a\u0e08.\u0e21\u0e35\u0e0a\u0e47\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 63113 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 1168\/90  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569022545\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e1f\u0e1e\u0e35 \u0e01\u0e23\u0e35\u0e19\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022545 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e1f\u0e1e\u0e35 \u0e01\u0e23\u0e35\u0e19\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2b\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e1c\u0e31\u0e01\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0143569001210\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e25\u0e29\u0e32 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001210 \u0e2b\u0e08.\u0e0a\u0e25\u0e29\u0e32 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c 2569-07-21 5000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004750\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e07\u0e25\u0e35\u0e48\u0e2b\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004750 \u0e1a\u0e08.\u0e16\u0e07\u0e25\u0e35\u0e48\u0e2b\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e35\u0e19\u0e34\u0e04\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 (\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19) (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u533b\u7642\u30fb\u798f\u7949 69  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e40\u0e21\u0e28\u0e27\u0e23 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0175569000495\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000495 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038220\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038220 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 552\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038238\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19 \u0e1a\u0e31\u0e19\u0e1a\u0e31\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038238 \u0e1a\u0e08.\u0e0b\u0e34\u0e19 \u0e1a\u0e31\u0e19\u0e1a\u0e31\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 (hr outsourcing) \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 (hr dispatch) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 230  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0345569003328\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e23\u0e13\u0e35 \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e34\u0e27\u0e2a\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003328 \u0e1a\u0e08.\u0e1e\u0e23\u0e23\u0e13\u0e35 \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e34\u0e27\u0e2a\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/3  \u0e16\u0e19\u0e19\u0e41\u0e01\u0e49\u0e27\u0e40\u0e2a\u0e19\u0e32 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0475569001642\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e0b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001642 \u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e0b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016371\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e2d\u0e40\u0e21\u0e34\u0e19\u0e17 \u0e2a\u0e40\u0e1b\u0e2a \u0e04\u0e38\u0e4a\u0e01\u0e01\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016371 \u0e1a\u0e08.\u0e40\u0e1f\u0e2d\u0e40\u0e21\u0e34\u0e19\u0e17 \u0e2a\u0e40\u0e1b\u0e2a \u0e04\u0e38\u0e4a\u0e01\u0e01\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u6559\u80b2 7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004705\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e31\u0e17\u0e18\u0e42\u0e19 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004705 \u0e1a\u0e08.\u0e21\u0e2b\u0e31\u0e17\u0e18\u0e42\u0e19 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e02\u0e38\u0e14 \u0e40\u0e08\u0e32\u0e30 \u0e25\u0e2d\u0e01 \u0e04\u0e39 \u0e04\u0e25\u0e2d\u0e07 \u0e25\u0e33\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07 \u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e36\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30 \u0e02\u0e38\u0e14\u0e1a\u0e48\u0e2d \u0e17\u0e33\u0e1d\u0e32\u0e22\u0e01\u0e31\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e17\u0e33\u0e16\u0e19\u0e19 \u0e44\u0e16\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u5efa\u8a2d 123\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0625569000814\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000814 \u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d \u0e17\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a oil&gas \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0805569002807\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e2d\u0e2d\u0e22\u0e25\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002807 \u0e1a\u0e08.\u0e14\u0e34\u0e19\u0e41\u0e14\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e2d\u0e2d\u0e22\u0e25\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e17\u0e30\u0e25\u0e32\u0e22\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e14\u0e34\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013418\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e25\u0e38\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013418 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e25\u0e38\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 40\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013434\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e0a\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013434 \u0e1a\u0e08.\u0e1e\u0e32\u0e0a\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 62  \u0e0b\u0e2d\u0e22 1 (\u0e16.\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a) \u0e16\u0e19\u0e19\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013451\",\"name_th\":\"\u0e1a\u0e08.007 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013451 \u0e1a\u0e08.007 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 79\/6  \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e32\u0e2a\u0e34\u0e1a\u0e1b\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013469\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e21 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013469 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e21 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 38\/1  \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e32\u0e2a\u0e34\u0e1a\u0e1b\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013485\",\"name_th\":\"\u0e1a\u0e08.3 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013485 \u0e1a\u0e08.3 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 56101 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e1a\u0e39\u0e18 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 5\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010621\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c  \u0e44\u0e14\u0e23\u0e1f\u0e4c  \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010621 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c  \u0e44\u0e14\u0e23\u0e1f\u0e4c  \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e14\u0e2a\u0e35\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e07\u0e32 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e31\u0e14\u0e40\u0e07\u0e32 \u0e2f\u0e25\u0e2f \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e1a\u0e23\u0e01 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e04\u0e25\u0e31\u0e0a\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e1a\u0e32\u0e30 \u0e1e\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e1a\u0e32\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/15  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e22\u0e41\u0e2b\u0e25\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005970\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e40\u0e27\u0e19\u0e0b\u0e4c\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005970 \u0e1a\u0e08.\u0e2e\u0e32\u0e40\u0e27\u0e19\u0e0b\u0e4c\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 5000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35\u0e44\u0e2d1 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e19\u0e34\u0e0a \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569136419\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c-\u0e40\u0e0b\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136419 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c-\u0e40\u0e0b\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 333\/6  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136443\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35.\u0e17\u0e35.\u0e44\u0e2d \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136443 \u0e1a\u0e08.\u0e2d\u0e35.\u0e17\u0e35.\u0e44\u0e2d \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 47711 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/42   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a6 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1a \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 13 (\u0e41\u0e2a\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136460\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e27\u0e34\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136460 \u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e27\u0e34\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 (solar rooftop) \u0e23\u0e30\u0e1a\u0e1a \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e25\u0e2d\u0e22\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e01\u0e23\u0e34\u0e15 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e1f\u0e01\u0e23\u0e34\u0e15 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2a\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u88fd\u9020 11  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136478\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e19\u0e34\u0e17\u0e35 \u0e44\u0e25\u0e04\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136478 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e19\u0e34\u0e17\u0e35 \u0e44\u0e25\u0e04\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/54  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136508\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136508 \u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e44\u0e17\u0e22 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 79110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 488  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136664\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136664 \u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 46109 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e40\u0e0b\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136711\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e23\u0e38\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136711 \u0e1a\u0e08.\u0e1f\u0e23\u0e38\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e22\u0e49\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e15\u0e32\u0e21\u0e08\u0e38\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e42\u0e14\u0e22\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u904b\u8f38\u30fb\u7269\u6d41 88\/167  \u0e16\u0e19\u0e19\u0e25\u0e33\u0e44\u0e17\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024009\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e01\u0e21\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024009 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e01\u0e21\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 158\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027334\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e1a\u0e2d\u0e23\u0e4c\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027334 \u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e1a\u0e2d\u0e23\u0e4c\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2a\u0e35\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e42\u0e04\u0e21\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c         \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 333\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027415\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e07\u0e40\u0e15\u0e48\u0e32 \u0e27\u0e34\u0e19\u0e40\u0e17\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027415 \u0e1a\u0e08.\u0e0a\u0e34\u0e07\u0e40\u0e15\u0e48\u0e32 \u0e27\u0e34\u0e19\u0e40\u0e17\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19 (point of sale) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19 (point of sale) \u0e1b\u0e49\u0e32\u0e22\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e27\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002526\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e02\u0e24\u0e17\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002526 \u0e2b\u0e08.\u0e2a\u0e38\u0e02\u0e24\u0e17\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2569-07-20 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e30 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u5efa\u8a2d 90\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022278\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e21\u0e1e\u0e25\u0e35\u0e17\u0e25\u0e35 \u0e27\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022278 \u0e1a\u0e08.\u0e04\u0e2d\u0e21\u0e1e\u0e25\u0e35\u0e17\u0e25\u0e35 \u0e27\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 5\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569037924\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c \u0e40\u0e04\u0e2a \u0e2d\u0e34\u0e19\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46592\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46592\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037924 \u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c \u0e40\u0e04\u0e2a \u0e2d\u0e34\u0e19\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 46592 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e1e\u0e47\u0e04\u0e01\u0e34\u0e49\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e1e\u0e32\u0e40\u0e25\u0e17\u0e44\u0e21\u0e49 \u0e25\u0e31\u0e07\u0e44\u0e21\u0e49 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e47\u0e04\u0e01\u0e34\u0e49\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 324\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038041\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e07\u0e2b\u0e07\u0e29\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17012\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17012\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038041 \u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e07\u0e2b\u0e07\u0e29\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 17012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e41\u0e02\u0e47\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0a\u0e19\u0e34\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29 (specialty paper) \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e23\u0e32\u0e04\u0e32 (\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e23\u0e21\u0e27\u0e34\u0e18\u0e35\u0e17\u0e33\u0e21\u0e37\u0e2d (handmade paper) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30 \u88fd\u9020 2\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038076\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e32\u0e27\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038076 \u0e1a\u0e08.\u0e17\u0e32\u0e27\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 129\/13  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e11\u0e39\u0e23\u0e22\u0e4c\u0e14\u0e33\u0e23\u0e34 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0385569000507\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e2a\u0e38\u0e02159 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000507 \u0e1a\u0e08.\u0e21\u0e35\u0e2a\u0e38\u0e02159 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 159  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006971\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e19 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006971 \u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e19 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u533b\u7642\u30fb\u798f\u7949 989\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016321\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e1a\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b 88 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016321 \u0e1a\u0e08.\u0e0a\u0e1a\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b 88 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u5bbf\u6cca\u30fb\u98f2\u98df 28  \u0e0b\u0e2d\u0e22 1 \u0e02 \u0e16\u0e19\u0e19\u0e17\u0e38\u0e48\u0e07\u0e42\u0e2e\u0e40\u0e15\u0e47\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000775\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e23\u0e19\u0e25\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000775 \u0e2b\u0e08.\u0e2d\u0e23\u0e19\u0e25\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-20 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e30 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u5efa\u8a2d 231  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0625569000806\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000806 \u0e1a\u0e08.\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23\u0e02\u0e38\u0e19 \u0e2a\u0e38\u0e01\u0e23\u0e1e\u0e48\u0e2d\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e38\u0e01\u0e23\u0e41\u0e21\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u8fb2\u6797\u6c34\u7523 194  \u0e0b\u0e2d\u0e22 4 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0673569000537\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e1b\u0e34\u0e07\u0e2b\u0e21\u0e39\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e40\u0e1a\u0e17\u0e32\u0e42\u0e01\u0e23\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0673569000537 \u0e2b\u0e08.\u0e2d\u0e32\u0e1b\u0e34\u0e07\u0e2b\u0e21\u0e39\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e40\u0e1a\u0e17\u0e32\u0e42\u0e01\u0e23 2569-07-20 5000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e44\u0e01\u0e48\u0e2a\u0e14 \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0815569002173\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002173 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e17\u0e33\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e34\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e41\u0e08\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e08\u0e49\u0e07\u0e2d\u0e2d\u0e01\u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e35\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 27  \u0e16\u0e19\u0e19\u0e19\u0e32\u0e17\u0e23\u0e32\u0e22 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0843569001418\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001418 \u0e2b\u0e08.\u0e19\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c 2569-07-20 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 48\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005929\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e0a\u0e23\u0e02\u0e38\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005929 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e0a\u0e23\u0e02\u0e38\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 650\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 (\u0e2a\u0e32\u0e22\u0e40\u0e2d\u0e0a\u0e35\u0e22) \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569136001\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136001 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 400\/131  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c2\u0e1a\u0e32\u0e07\u0e19\u0e32\u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023843\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e2a \u0e44\u0e27\u0e1a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023843 \u0e1a\u0e08.\u0e40\u0e04\u0e2a \u0e44\u0e27\u0e1a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e2a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 363  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027229\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e13365  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027229 \u0e1a\u0e08.\u0e04\u0e39\u0e13365  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 189\/6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e23\u0e35\u0e21\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0155569000576\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000576 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 5000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0383569000271\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0383569000271 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-18 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0463569000750\",\"name_th\":\"\u0e2b\u0e08.\u0e10\u0e34\u0e1b\u0e23\u0e30\u0e20\u0e32\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000750 \u0e2b\u0e08.\u0e10\u0e34\u0e1b\u0e23\u0e30\u0e20\u0e32 2569-07-18 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 93  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0725569002158\",\"name_th\":\"\u0e1a\u0e08.108 \u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002158 \u0e1a\u0e08.108 \u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e1c\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c (inverter) \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e22\u0e36\u0e14\u0e08\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u5efa\u8a2d 55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0805569002751\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e41\u0e2a\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002751 \u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e41\u0e2a\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013329\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e22\u0e32 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013329 \u0e1a\u0e08.\u0e23\u0e32\u0e22\u0e32 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 5000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 114\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569134939\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e27\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134939 \u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e27\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e23\u0e31\u0e07\u0e2a\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 151  \u0e16\u0e19\u0e19\u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135081\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135081 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/99  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135455\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135455 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e2d\u0e37\u0e48\u0e19\u0e41\u0e01\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u91d1\u878d\u30fb\u4fdd\u967a 191\/1  \u0e16\u0e19\u0e19\u0e40\u0e22\u0e47\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135471\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e44\u0e1e\u0e23\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135471 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e44\u0e1e\u0e23\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/68  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135528\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d \u0e04\u0e32\u0e0b\u0e48\u0e32 \u0e42\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135528 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d \u0e04\u0e32\u0e0b\u0e48\u0e32 \u0e42\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63  \u0e0b\u0e2d\u0e22 \u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135552\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e41\u0e25\u0e04\u0e0b\u0e35\u0e48 \u0e14\u0e35\u0e0b\u0e35 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135552 \u0e1a\u0e08.\u0e01\u0e32\u0e41\u0e25\u0e04\u0e0b\u0e35\u0e48 \u0e14\u0e35\u0e0b\u0e35 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23p23 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023657\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e27\u0e34\u0e19 \u0e1e\u0e23\u0e2d\u0e2a \u0e40\u0e1e\u0e2d\u0e30\u0e23\u0e34\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023657 \u0e1a\u0e08.\u0e21\u0e32\u0e27\u0e34\u0e19 \u0e1e\u0e23\u0e2d\u0e2a \u0e40\u0e1e\u0e2d\u0e30\u0e23\u0e34\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e42\u0e2d\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 417  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023681\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e04\u0e35\u0e27\u0e34\u0e0a\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e17\u0e35\u0e1f \u0e42\u0e04\u0e49\u0e17\u0e15\u0e34\u0e49\u0e07\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20221\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20221\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023681 \u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e04\u0e35\u0e27\u0e34\u0e0a\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e17\u0e35\u0e1f \u0e42\u0e04\u0e49\u0e17\u0e15\u0e34\u0e49\u0e07\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 20221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 2\/3  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e32\u0e07\u0e19\u0e32\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1611-03 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 16 \u0e22\u0e39\u0e19\u0e34\u0e15 \u0e40\u0e2d \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023711\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e01-\u0e44\u0e19\u0e19\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023711 \u0e1a\u0e08.\u0e0b\u0e34\u0e01-\u0e44\u0e19\u0e19\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 187  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023746\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e13\u0e01\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023746 \u0e1a\u0e08.\u0e18\u0e13\u0e01\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 (turnkey) \u5efa\u8a2d 99\/155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0133569002500\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e33\u0e23\u0e07\u0e04\u0e4c\u0e0a\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002500 \u0e2b\u0e08.\u0e14\u0e33\u0e23\u0e07\u0e04\u0e4c\u0e0a\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2569-07-17 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e30 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u5efa\u8a2d 90\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002518\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e34\u0e48\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07999\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002518 \u0e2b\u0e08.\u0e21\u0e34\u0e48\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07999 2569-07-17 5000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 161\/359  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e2b\u0e30\u0e2f\u0e04\u0e25\u0e2d\u0e077 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 klong 7 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569009513\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e15\u0e34\u0e42\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009513 \u0e1a\u0e08.\u0e25\u0e32\u0e15\u0e34\u0e42\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 25999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 913\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0635569001489\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33\u0e27\u0e34\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64925\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64925\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001489 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33\u0e27\u0e34\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 64925 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e42\u0e23\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u91d1\u878d\u30fb\u4fdd\u967a 211\/2,211\/3  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e17\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0745569007591\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d.\u0e40\u0e2d\u0e2a.\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007591 \u0e1a\u0e08.\u0e40\u0e2d.\u0e40\u0e2d\u0e2a.\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e15\u0e32\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 11\/16  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e19\u0e35\u0e42\u0e2d 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0765569001500\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001500 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e4d\u0e49\u0e32\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e01\u0e4a\u0e32\u0e0b\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0905569005881\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005881 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569134475\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e42\u0e1b\u0e23 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134475 \u0e1a\u0e08.\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e42\u0e1b\u0e23 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 133\/179  \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134599\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e14\u0e32 \u0e1a\u0e25\u0e2d\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134599 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e14\u0e32 \u0e1a\u0e25\u0e2d\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e15\u0e23\u0e35 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e30\u0e1e\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e40\u0e1b\u0e49 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2b\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07  \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34  \u0e0b\u0e2d\u0e22 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e32\u0e23\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e3518 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134718\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01302\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01302\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134718 \u0e1a\u0e08.\u0e41\u0e04\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 01302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e1e\u0e32\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e15\u0e49\u0e19\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e34\u0e48\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01 \u8fb2\u6797\u6c34\u7523 99\/21  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e1a\u0e32\u0e07\u0e19\u0e32- \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134726\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e41\u0e2a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134726 \u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e41\u0e2a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e32\u0e22\u0e32\u0e01\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e04\u0e32\u0e23\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289\/5  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023568\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e15\u0e34\u0e40\u0e21\u0e17 \u0e40\u0e2d\u0e1f 4 \u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023568 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e15\u0e34\u0e40\u0e21\u0e17 \u0e40\u0e2d\u0e1f 4 \u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 33\/99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023584\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e31\u0e15\u0e23\u0e4c\u0e08\u0e34\u0e23\u0e32\u0e20\u0e32 \u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023584 \u0e1a\u0e08.\u0e09\u0e31\u0e15\u0e23\u0e4c\u0e08\u0e34\u0e23\u0e32\u0e20\u0e32 \u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e2b\u0e34\u0e49\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19  \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026851\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24320\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24320\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026851 \u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 24320 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e25\u0e2d\u0e21 \u0e2b\u0e25\u0e48\u0e2d\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e25\u0e2b\u0e30\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u88fd\u9020 1\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0145569004687\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e20\u0e39\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10752\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10752\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004687 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e20\u0e39\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 10752 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 153\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e0a\u0e31\u0e22\u0e21\u0e07\u0e04\u0e255 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569037461\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037461 \u0e1a\u0e08.\u0e01\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e39\u0e23\u0e13\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 24\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0405569006903\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e21\u0e32\u0e23\u0e34\u0e44\u0e17\u0e21\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006903 \u0e1a\u0e08.\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e21\u0e32\u0e23\u0e34\u0e44\u0e17\u0e21\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0465569000883\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e2a\u0e32\u0e19\u0e08\u0e31\u0e2a \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000883 \u0e1a\u0e08.\u0e2d\u0e35\u0e2a\u0e32\u0e19\u0e08\u0e31\u0e2a \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e44\u0e2a\u0e49\u0e01\u0e23\u0e2d\u0e01\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0505569016061\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e0a\u0e32 \u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016061 \u0e1a\u0e08.\u0e23\u0e32\u0e0a\u0e32 \u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 88\/15  \u0e0b\u0e2d\u0e22 22 \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e15\u0e19\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016118\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35 \u0e04\u0e32\u0e23\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016118 \u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35 \u0e04\u0e32\u0e23\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c  \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 13\/3  \u0e0b\u0e2d\u0e22 7 (\u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e32\u0e23\u0e14\u0e32) \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e32\u0e23\u0e14\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000767\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 199\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000767 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 199 2569-07-16 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e30 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u5efa\u8a2d 126\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0533569000520\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c\u0e1e\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0533569000520 \u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c\u0e1e\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-16 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0735569007231\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e25\u0e34\u0e2a \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007231 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e25\u0e34\u0e2a \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 20121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e2a\u0e21 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007516\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e40\u0e04\u0e48\u0e2d \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007516 \u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e40\u0e04\u0e48\u0e2d \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e23\u0e48\u0e32\u0e07\u0e41\u0e2a\u0e14\u0e07\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 115\/242  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0775569003049\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22 \u0e1f\u0e35\u0e14 \u0e21\u0e34\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10802\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10802\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003049 \u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22 \u0e1f\u0e35\u0e14 \u0e21\u0e34\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 10802 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e43\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u88fd\u9020 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0825569001151\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e42\u0e01 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001151 \u0e1a\u0e08.\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e42\u0e01 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 5000000 46202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e49\u0e19\u0e01\u0e25\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0105569133550\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46614\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46614\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133550 \u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 46614 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/22  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1954\u0e41\u0e22\u0e014(\u0e21.\u0e27\u0e25\u0e35\u0e27\u0e31\u0e25\u0e22\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133606\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133606 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47732 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e2b\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184\/11  \u0e0b\u0e2d\u0e22 \u0e15\u0e23\u0e2d\u0e01\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133622\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e1a\u0e23\u0e32\u0e2e\u0e34\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e0a\u0e15\u0e34\u0e2d\u0e31\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133622 \u0e1a\u0e08.\u0e2d\u0e34\u0e1a\u0e23\u0e32\u0e2e\u0e34\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e0a\u0e15\u0e34\u0e2d\u0e31\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47732 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e15\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184\/11  \u0e0b\u0e2d\u0e22 \u0e15\u0e23\u0e2d\u0e01\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133665\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133665 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 45302 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184\/11 \u0e15\u0e23\u0e2d\u0e01 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133690\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e35\u0e48 \u0e40\u0e19\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e2e\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133690 \u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e35\u0e48 \u0e40\u0e19\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e2e\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e04\u0e2d\u0e23\u0e4c\u0e14 \u0e41\u0e1f\u0e25\u0e15 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u4e0d\u52d5\u7523 270,272,274  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133746\",\"name_th\":\"\u0e1a\u0e08.89 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133746 \u0e1a\u0e08.89 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 2828  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133801\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e19\u0e31\u0e2a \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133801 \u0e1a\u0e08.\u0e2d\u0e32\u0e19\u0e31\u0e2a \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47732 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e2b\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 484  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 46 \u0e16\u0e19\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 46 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133886\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e14\u0e14\u0e35\u0e49\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e40\u0e0b\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133886 \u0e1a\u0e08.\u0e40\u0e23\u0e14\u0e14\u0e35\u0e49\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e40\u0e0b\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 45102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01  \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01   \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27\u0e41\u0e25\u0e30\u0e16\u0e31\u0e07\u0e1e\u0e48\u0e27\u0e07(\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c) \u0e23\u0e16\u0e01\u0e36\u0e48\u0e07\u0e1e\u0e48\u0e27\u0e07 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/1  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026541\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e30\u0e15\u0e34\u0e4a\u0e1a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026541 \u0e1a\u0e08.\u0e01\u0e23\u0e30\u0e15\u0e34\u0e4a\u0e1a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2d\u0e1a \u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 79\/18-19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026613\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e1e\u0e32\u0e2a \u0e28\u0e23\u0e35\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026613 \u0e1a\u0e08.\u0e40\u0e25\u0e1e\u0e32\u0e2a \u0e28\u0e23\u0e35\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 45101 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e01\u0e25\u0e44\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 245  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0155569000568\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e41\u0e1a\u0e04\u0e42\u0e2e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46592\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46592\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000568 \u0e1a\u0e08.\u0e1a\u0e35 \u0e41\u0e1a\u0e04\u0e42\u0e2e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 46592 \u0e41\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569037347\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e31\u0e12\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037347 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e31\u0e12\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037371\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e49\u0e32\u0e44\u0e17\u0e22\u0e44\u0e21\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08102\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08102\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037371 \u0e1a\u0e08.\u0e40\u0e01\u0e49\u0e32\u0e44\u0e17\u0e22\u0e44\u0e21\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 08102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e2b\u0e34\u0e19\u0e41\u0e25\u0e30\u0e22\u0e48\u0e2d\u0e22\u0e2b\u0e34\u0e19 \u9271\u696d\u30fb\u63a1\u77f3 99\/101  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 9999 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e2e\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009467\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e41\u0e17\u0e23\u0e47\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"61900\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"61900\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009467 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e41\u0e17\u0e23\u0e47\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 61900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002241\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002241 \u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e41\u0e1c\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003850\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e2b\u0e25\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003850 \u0e1a\u0e08.\u0e08\u0e39\u0e2b\u0e25\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 10799 \u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e42\u0e25\u0e2b\u0e30, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e15\u0e31\u0e14\u0e42\u0e25\u0e2b\u0e30, \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01, \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c, \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19, \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b,  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19, \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d, \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u88fd\u9020 18\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002047\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e02\u0e1a\u0e38\u0e0d\u0e1b\u0e31\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002047 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e02\u0e1a\u0e38\u0e0d\u0e1b\u0e31\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 145\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569002055\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e01\u0e23 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002055 \u0e1a\u0e08.\u0e19\u0e34\u0e01\u0e23 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569002071\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e07\u0e44\u0e0a\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002071 \u0e1a\u0e08.\u0e18\u0e07\u0e44\u0e0a\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007315\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e10\u0e1e\u0e35\u0e27\u0e32\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007315 \u0e1a\u0e08.\u0e1b\u0e10\u0e1e\u0e35\u0e27\u0e32\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 42909 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5efa\u8a2d 301\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0363569000904\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e25\u0e34\u0e15\u0e322016\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000904 \u0e2b\u0e08.\u0e25\u0e25\u0e34\u0e15\u0e322016 2569-07-15 5000000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e21\u0e2d\u0e1a\u0e01\u0e23\u0e2d\u0e1a \u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21\u0e1b\u0e35\u0e4a\u0e1a \u0e02\u0e19\u0e21\u0e2a\u0e2d\u0e14\u0e44\u0e2a\u0e49 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e1e\u0e32\u0e22 \u0e17\u0e32\u0e23\u0e4c\u0e15 \u0e0a\u0e34\u0e1f\u0e1f\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 218  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0405569006831\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e1f\u0e15\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006831 \u0e1a\u0e08.\u0e01\u0e34\u0e1f\u0e15\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 235\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006849\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006849 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e22\u0e35\u0e19\u0e2a\u0e4c\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e38\u0e14\u0e19\u0e2d\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14\u0e0a\u0e38\u0e14\u0e40\u0e14\u0e23\u0e2a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e04\u0e25\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e23\u0e38\u0e29\u0e41\u0e25\u0e30\u0e2a\u0e15\u0e23\u0e35 \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 235\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006857\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e47\u0e2d\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006857 \u0e1a\u0e08.\u0e1f\u0e47\u0e2d\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 58202 \u0e23\u0e31\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c  \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 42  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e0b\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0455569001472\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e17\u0e23\u0e32\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001472 \u0e1a\u0e08.\u0e40\u0e21\u0e17\u0e23\u0e32\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 109  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0475569001545\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e41\u0e21\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001545 \u0e1a\u0e08.\u0e21\u0e35\u0e41\u0e21\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015995\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e27\u0e4c \u0e40\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e31\u0e25 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015995 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e27\u0e4c \u0e40\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e31\u0e25 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0535569000785\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000785 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0765569001496\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23953\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23953\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001496 \u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 23953 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1c\u0e2a\u0e21\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e2d\u0e2a\u0e1f\u0e31\u0e25\u0e15\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e07\u0e21\u0e30\u0e15\u0e2d\u0e22 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e25\u0e39\u0e01\u0e23\u0e31\u0e07 \u0e2d\u0e34\u0e10 \u0e1a\u0e25\u0e47\u0e2d\u0e01 \u0e17\u0e48\u0e2d\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 32\/22  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e25\u0e35 1 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0825569001134\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e2d\u0e17 \u0e40\u0e2a\u0e21\u0e47\u0e14\u0e19\u0e32\u0e07\u0e0a\u0e35 \u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001134 \u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e2d\u0e17 \u0e40\u0e2a\u0e21\u0e47\u0e14\u0e19\u0e32\u0e07\u0e0a\u0e35 \u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e41\u0e02\u0e01 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e31\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14 \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e14\u0e49\u0e32\u0e19\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569013078\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"13929\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"13929\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013078 \u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 13929 \u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e40\u0e40\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u88fd\u9020 9\/128  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e23\u0e34\u0e40\u0e1e\u0e25\u0e2a \u0e41\u0e2d\u0e23\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013116\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e31\u0e1a\u0e17\u0e34\u0e21\u0e17\u0e2d\u0e07 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013116 \u0e1a\u0e08.\u0e17\u0e31\u0e1a\u0e17\u0e34\u0e21\u0e17\u0e2d\u0e07 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e16\u0e15\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013132\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013132 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 255\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569132987\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e1a\u0e14\u0e38\u0e25 \u0e0b\u0e31\u0e15\u0e15\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46492\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46492\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132987 \u0e1a\u0e08.\u0e2d\u0e31\u0e1a\u0e14\u0e38\u0e25 \u0e0b\u0e31\u0e15\u0e15\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 46492 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e2b\u0e34\u0e19 \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184\/11  \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133118\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e0a \u0e1a\u0e34\u0e2a\u0e42\u0e15\u0e23 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133118 \u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e0a \u0e1a\u0e34\u0e2a\u0e42\u0e15\u0e23 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6\/52  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27101 \u0e0b\u0e2d\u0e2242 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133134\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e17\u0e35. \u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e40\u0e17\u0e2d\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133134 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e17\u0e35. \u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e40\u0e17\u0e2d\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6\/52  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27101 \u0e0b\u0e2d\u0e2242 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133142\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35.\u0e40\u0e2d\u0e1f.\u0e17\u0e35. \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133142 \u0e1a\u0e08.\u0e08\u0e35.\u0e40\u0e2d\u0e1f.\u0e17\u0e35. \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6\/52  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27101 \u0e0b\u0e2d\u0e2242 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133312\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e48\u0e27\u0e07\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e48\u0e2d \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133312 \u0e1a\u0e08.\u0e0a\u0e48\u0e27\u0e07\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e48\u0e2d \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 20299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e21\u0e35\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23p23 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133321\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e1e\u0e25\u0e31\u0e2a \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133321 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e1e\u0e25\u0e31\u0e2a \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e44\u0e21\u0e48\u0e1c\u0e48\u0e32\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 1179  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133339\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e1a\u0e35.\u0e1e\u0e35 \u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133339 \u0e1a\u0e08.\u0e40\u0e04.\u0e1a\u0e35.\u0e1e\u0e35 \u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 82 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023282\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e19\u0e44\u0e17\u0e22\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023282 \u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e19\u0e44\u0e17\u0e22\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e19 \u0e1a\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e23\u0e49\u0e2d\u0e19 \u0e1a\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e2d\u0e38\u0e48\u0e19 \u0e1a\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e0a\u0e48\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 888\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026478\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026478 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e27\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e32\u0e22 \u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u88fd\u9020 122\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037142\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e2a\u0e34\u0e23\u0e34 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037142 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e2a\u0e34\u0e23\u0e34 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 139\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037169\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e1f\u0e42\u0e15\u0e42\u0e27\u0e25\u0e40\u0e17\u0e2d\u0e34\u0e01 \u0e01\u0e25\u0e32\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037169 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e1f\u0e42\u0e15\u0e42\u0e27\u0e25\u0e40\u0e17\u0e2d\u0e34\u0e01 \u0e01\u0e25\u0e32\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 43210 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e42\u0e1f\u0e42\u0e15\u0e42\u0e27\u0e25\u0e40\u0e17\u0e2d\u0e34\u0e01 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e01\u0e23\u0e30\u0e08\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e25\u0e32\u0e21\u0e34\u0e40\u0e19\u0e15 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e09\u0e19\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e30\u0e08\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 252\/211  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e09\u0e31\u0e15\u0e23\u0e17\u0e2d\u0e07\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037207\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e07\u0e2b\u0e22\u0e38\u0e19 \u0e44\u0e17\u0e21\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037207 \u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e07\u0e2b\u0e22\u0e38\u0e19 \u0e44\u0e17\u0e21\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 72109 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 240\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037291\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e32\u0e19\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037291 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e32\u0e19\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 300\/106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009335\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e08\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009335 \u0e1a\u0e08.\u0e0b\u0e34\u0e08\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 615\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003833\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1e\u0e25\u0e35\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003833 \u0e1a\u0e08.\u0e40\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1e\u0e25\u0e35\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 22299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u88fd\u9020 915\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002021\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e08 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002021 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e08 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u5efa\u8a2d 353  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0365569001449\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e34\u0e29\u0e10\u0e4c\u0e1b\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001449 \u0e1a\u0e08.\u0e1e\u0e23\u0e34\u0e29\u0e10\u0e4c\u0e1b\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e23\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 (\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 285  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0405569006792\",\"name_th\":\"\u0e1a\u0e08. \u0e14\u0e34 \u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006792 \u0e1a\u0e08. \u0e14\u0e34 \u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e23\u0e49\u0e32\u0e19\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a \u0e2a\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 449\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 27 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006806\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e08 \u0e40\u0e27\u0e42\u0e23\u0e48 \u0e40\u0e25\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006806 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e08 \u0e40\u0e27\u0e42\u0e23\u0e48 \u0e40\u0e25\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2b\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e41\u0e17\u0e49 \u0e2b\u0e19\u0e31\u0e07\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 449\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 27 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0655569002272\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002272 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 309  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0735569007095\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e1e\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007095 \u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e1e\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e33\u0e02\u0e49\u0e32\u0e27 \u0e23\u0e33\u0e2a\u0e01\u0e31\u0e14 \u0e23\u0e33\u0e02\u0e49\u0e32\u0e27 \u0e01\u0e32\u0e01\u0e16\u0e31\u0e48\u0e27\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e1c\u0e34\u0e27\u0e16\u0e31\u0e48\u0e27\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e23\u0e33\u0e2a\u0e32\u0e25\u0e35 \u0e1b\u0e25\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27 \u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e21\u0e31\u0e19\u0e40\u0e2a\u0e49\u0e19 \u0e01\u0e32\u0e01\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e01\u0e23\u0e30\u0e16\u0e34\u0e19 \u0e23\u0e33\u0e2b\u0e22\u0e32\u0e1a \u0e41\u0e01\u0e25\u0e1a \u0e01\u0e33\u0e21\u0e30\u0e16\u0e31\u0e19  \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e1b\u0e38\u0e4b\u0e22 \u0e40\u0e01\u0e25\u0e37\u0e2d \u0e2d\u0e42\u0e01\u0e23\u0e21\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e32\u0e23\u0e2b\u0e27\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0835569012969\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e4c\u0e25\u0e35\u0e48 \u0e2a\u0e27\u0e32\u0e1e\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012969 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e4c\u0e25\u0e35\u0e48 \u0e2a\u0e27\u0e32\u0e1e\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 90\/1  \u0e16\u0e19\u0e19\u0e23\u0e30\u0e19\u0e2d\u0e07 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013035\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e19\u0e2a\u0e17\u0e4c \u0e01\u0e30\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013035 \u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e19\u0e2a\u0e17\u0e4c \u0e01\u0e30\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 162\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010320\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e01\u0e22\u0e2d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010320 \u0e1a\u0e08.\u0e2a\u0e38\u0e01\u0e22\u0e2d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005741\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04 69 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005741 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04 69 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 5000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e15\u0e25\u0e2d\u0e14 \u0e08\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 54\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569132081\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e25\u0e4c\u0e21\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132081 \u0e1a\u0e08.\u0e40\u0e2d\u0e25\u0e4c\u0e21\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 11  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 48 \u0e41\u0e22\u0e01 49\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132111\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132111 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07  \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e04\u0e33\u0e19\u0e27\u0e13 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e02\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 333\/23  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e40\u0e1a\u0e25\u0e25\u0e48\u0e32 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132138\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132138 \u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 96309 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 16  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 88 (\u0e2d\u0e23\u0e1e\u0e34\u0e19) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132154\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e40\u0e1e\u0e25\u0e17 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132154 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e40\u0e1e\u0e25\u0e17 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 735 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132324\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e27\u0e19\u0e40\u0e2d\u0e49\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132324 \u0e1a\u0e08.\u0e2e\u0e27\u0e19\u0e40\u0e2d\u0e49\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 (solar rooftop) \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 1010  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e34\u0e19\u0e27\u0e31\u0e15\u0e23\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c 3 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 32 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132375\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e44\u0e17\u0e48 \u0e40\u0e08\u0e34\u0e49\u0e07\u0e40\u0e15\u0e4b\u0e2d \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132375 \u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e44\u0e17\u0e48 \u0e40\u0e08\u0e34\u0e49\u0e07\u0e40\u0e15\u0e4b\u0e2d \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 32909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (oem) \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e40\u0e15\u0e49\u0e32\u0e2b\u0e39\u0e49 \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e40\u0e1a\u0e19\u0e42\u0e17\u0e44\u0e19\u0e15\u0e4c \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e41\u0e23\u0e48 \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e1c\u0e2a\u0e21 \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49 \u88fd\u9020 420\/104  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 - \u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132430\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e0b\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132430 \u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e0b\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 97\/107  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 17 \u0e41\u0e22\u0e01 18 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132472\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e24\u0e15\u0e04\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132472 \u0e1a\u0e08.\u0e01\u0e24\u0e15\u0e04\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/1  \u0e0b\u0e2d\u0e22 10 \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132537\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e40\u0e21\u0e47\u0e01\u0e0b\u0e4c\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01115\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01115\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132537 \u0e1a\u0e08.\u0e2d\u0e34\u0e40\u0e21\u0e47\u0e01\u0e0b\u0e4c\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 01115 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 728 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132545\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e2a\u0e23\u0e35 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132545 \u0e1a\u0e08.\u0e2d\u0e31\u0e2a\u0e23\u0e35 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e01\u0e31\u0e19\u0e44\u0e1f \u0e01\u0e31\u0e19\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e09\u0e19\u0e27\u0e19\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e4a\u0e32\u0e0b \u0e2b\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e27\u0e32\u0e25\u0e4c\u0e27 \u0e2a\u0e1b\u0e23\u0e34\u0e07\u0e40\u0e01\u0e25\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/4  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e22\u0e39\u0e19\u0e34\u0e15 \u0e40\u0e2d \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023142\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e34\u0e19\u0e30 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023142 \u0e1a\u0e08.\u0e2e\u0e34\u0e19\u0e30 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1596\/121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023151\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e15\u0e15\u0e2d\u0e19 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023151 \u0e1a\u0e08.\u0e04\u0e2d\u0e15\u0e15\u0e2d\u0e19 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 1598  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023177\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e42\u0e04\u0e48 \u0e42\u0e23\u0e42\u0e1a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023177 \u0e1a\u0e08.\u0e14\u0e39\u0e42\u0e04\u0e48 \u0e42\u0e23\u0e42\u0e1a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e44\u0e1f\u0e1f\u0e49\u0e32 (electromechanical equipment) \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 (automation system) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/555  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a.\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e1a\u0e35-1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026273\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e32\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026273 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e32\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 89\/131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021506\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e49\u0e14 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021506 \u0e1a\u0e08.\u0e01\u0e39\u0e49\u0e14 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 47612 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/2476  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0165569001602\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e2a\u0e01\u0e34\u0e25\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001602 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e2a\u0e01\u0e34\u0e25\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001611\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e41\u0e2d\u0e1e\u0e1e\u0e32\u0e40\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001611 \u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e41\u0e2d\u0e1e\u0e1e\u0e32\u0e40\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 3\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036952\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e27\u0e35\u0e48\u0e2e\u0e48\u0e27\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036952 \u0e1a\u0e08.\u0e0b\u0e27\u0e35\u0e48\u0e2e\u0e48\u0e27\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e14\u0e25\u0e2d\u0e07 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19 (virtual reality) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e2d\u0e1b\u0e42\u0e15\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14 \u0e0a\u0e34\u0e1b\u0e27\u0e07\u0e08\u0e23\u0e23\u0e27\u0e21 (ic) \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e27\u0e07\u0e08\u0e23\u0e23\u0e27\u0e21 \u60c5\u5831\u901a\u4fe1\u30fbit 41\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037002\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e34\u0e2a\u0e17\u0e35\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037002 \u0e1a\u0e08.\u0e1e\u0e23\u0e34\u0e2a\u0e17\u0e35\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04 \u0e44\u0e2d\u0e17\u0e35 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b1\/5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0315569001881\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001881 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e27\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e32\u0e22 \u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u88fd\u9020 219\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0415569003637\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e1e\u0e32\u0e2a \u0e11\u0e35\u0e06\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003637 \u0e1a\u0e08.\u0e40\u0e25\u0e1e\u0e32\u0e2a \u0e11\u0e35\u0e06\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 756  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e07\u0e40\u0e04\u0e47\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0455569001430\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e39\u0e14 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001430 \u0e1a\u0e08.\u0e27\u0e39\u0e14 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e2a\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e44\u0e21\u0e49 \u0e42\u0e23\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u88fd\u9020 75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001448\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e17\u0e34\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001448 \u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e17\u0e34\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e2a\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e44\u0e21\u0e49 \u0e42\u0e23\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u88fd\u9020 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001456\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e35\u0e23\u0e0d\u0e32 159 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001456 \u0e1a\u0e08.\u0e18\u0e35\u0e23\u0e0d\u0e32 159 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e22\u0e48\u0e2d\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e22\u0e48\u0e2d\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a \u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33             \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 29\/4  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e27\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0495569000531\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e30\u0e2b\u0e27\u0e31\u0e19\u0e2d\u0e34\u0e21\u0e1b\u0e2d\u0e23\u0e4c\u0e15-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000531 \u0e1a\u0e08.\u0e2a\u0e30\u0e2b\u0e27\u0e31\u0e19\u0e2d\u0e34\u0e21\u0e1b\u0e2d\u0e23\u0e4c\u0e15-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46315 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 154\/3  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015766\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c \u0e25\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015766 \u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c \u0e25\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 116\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0655569002248\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e40\u0e14\u0e2d\u0e30\u0e2a\u0e40\u0e1b\u0e0b \u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002248 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e40\u0e14\u0e2d\u0e30\u0e2a\u0e40\u0e1b\u0e0b \u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 103\/8  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e44\u0e15\u0e23\u0e1b\u0e34\u0e0f\u0e01 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0725569002115\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e47\u0e21\u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e4c\u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47741\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47741\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002115 \u0e1a\u0e08.\u0e40\u0e02\u0e47\u0e21\u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e4c\u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 47741 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 555  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007044\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e19\u0e0b\u0e34\u0e25 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007044 \u0e1a\u0e08.\u0e40\u0e1e\u0e19\u0e0b\u0e34\u0e25 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 47612 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007354\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007354 \u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569012942\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e1f \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e04\u0e25\u0e31\u0e1a \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012942 \u0e1a\u0e08.\u0e42\u0e04\u0e1f \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e04\u0e25\u0e31\u0e1a \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 127\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0905569005716\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005716 \u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 5000000 47691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e1d\u0e32\u0e01 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e1e\u0e27\u0e07\u0e01\u0e38\u0e0d\u0e41\u0e08 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36,36\/1  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569131999\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35 189 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131999 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35 189 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e1e\u0e33\u0e19\u0e31\u0e01\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e1e\u0e33\u0e19\u0e31\u0e01\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 10\/317  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 93 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132006\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132006 \u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 5000000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u6559\u80b2 61  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0505569015758\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e34\u0e19\u0e25\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e41\u0e04\u0e23\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015758 \u0e1a\u0e08.\u0e2a\u0e01\u0e34\u0e19\u0e25\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e41\u0e04\u0e23\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 5000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569131808\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e27\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131808 \u0e1a\u0e08.\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e15\u0e31\u0e27\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 5000000 73101 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e23\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e42\u0e06\u0e29\u0e13\u0e32\u0e44\u0e1b\u0e25\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38\u0e41\u0e25\u0e30\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e15\u0e39\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1a\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2f\u0e25\u0e2f \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e23\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e27\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e13 \u0e08\u0e38\u0e14\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e32\u0e07\u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e15\u0e23\u0e07\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 5\/20  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569021441\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e17 \u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e40\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021441 \u0e1a\u0e08.\u0e2d\u0e35\u0e17 \u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e40\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 5000000 82302 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 105\/266  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e34 \u0e2d\u0e34\u0e40\u0e18\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e35\u0e19\u0e27\u0e39\u0e49\u0e14 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0575569004489\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e17\u0e2d\u0e07\u0e41\u0e17\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004489 \u0e1a\u0e08.\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e17\u0e2d\u0e07\u0e41\u0e17\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e41\u0e25\u0e30\u0e17\u0e2d\u0e07\u0e41\u0e17\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 834\/6  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0905569005694\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005694 \u0e1a\u0e08.\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 9  \u0e0b\u0e2d\u0e22 2 \u0e1a\u0e49\u0e32\u0e19\u0e43\u0e19\u0e44\u0e23\u0e48 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569130861\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e27 \u0e40\u0e0b\u0e34\u0e19 169 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130861 \u0e1a\u0e08.\u0e01\u0e32\u0e27 \u0e40\u0e0b\u0e34\u0e19 169 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 41001 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 2  \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 11 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130984\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e38\u0e13 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130984 \u0e1a\u0e08.\u0e2d\u0e23\u0e38\u0e13 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e1d\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e31\u0e01\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e1b\u0e35 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e1f\u0e25\u0e15 \u0e2b\u0e23\u0e37\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07 (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19) \u91d1\u878d\u30fb\u4fdd\u967a 388\/55  \u0e16\u0e19\u0e19\u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130992\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e2d\u0e32\u0e40\u0e15\u0e2d\u0e25\u0e34\u0e40\u0e22\u0e23\u0e4c \u0e44\u0e14\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130992 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e2d\u0e32\u0e40\u0e15\u0e2d\u0e25\u0e34\u0e40\u0e22\u0e23\u0e4c \u0e44\u0e14\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e2a\u0e40\u0e15\u0e47\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d (\u0e3abeef steak),\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07,\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 585\/213  \u0e16\u0e19\u0e19\u0e2d\u0e42\u0e28\u0e01-\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131123\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e31\u0e21\u0e23\u0e39\u0e25 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131123 \u0e1a\u0e08.\u0e04\u0e31\u0e21\u0e23\u0e39\u0e25 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/1  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 65 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131131\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e40\u0e0b\u0e34\u0e07 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131131 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e40\u0e0b\u0e34\u0e07 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1179\/43  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131166\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131166 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e01\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 51\/75  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e1566(\u0e2a\u0e22\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131361\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e2d\u0e42\u0e23\u0e2a\u0e40\u0e1b\u0e0b \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35\u0e04\u0e34\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"30300\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"30300\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131361 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e2d\u0e42\u0e23\u0e2a\u0e40\u0e1b\u0e0b \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35\u0e04\u0e34\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 30300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e44\u0e23\u0e49\u0e04\u0e19\u0e02\u0e31\u0e1a (drone,uav,uas) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u88fd\u9020 23  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 69 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131549\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e08 \u0e44\u0e17\u0e22 \u0e40\u0e1f\u0e23\u0e0a\u0e42\u0e01 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131549 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e08 \u0e44\u0e17\u0e22 \u0e40\u0e1f\u0e23\u0e0a\u0e42\u0e01 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 943\/6  \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002381\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e14\u0e35 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002381 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e14\u0e35 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-10 5000000 49323 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e17\u0e22 \u904b\u8f38\u30fb\u7269\u6d41 132\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026125\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e44\u0e17\u0e21\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026125 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e44\u0e17\u0e21\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 8\/2  \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c 46\/3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026176\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e2a\u0e15\u0e35\u0e25 2025 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026176 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e2a\u0e15\u0e35\u0e25 2025 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e41\u0e23\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021425\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e15\u0e40\u0e2e\u0e25\u0e18\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021425 \u0e1a\u0e08.\u0e1f\u0e34\u0e15\u0e40\u0e2e\u0e25\u0e18\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2d\u0e23\u0e4c\u0e42\u0e18\u0e1b\u0e34\u0e14\u0e34\u0e01\u0e2a\u0e4c (\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d) \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e2a\u0e2b\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u533b\u7642\u30fb\u798f\u7949 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569036596\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e25\u0e13\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036596 \u0e1a\u0e08.\u0e14\u0e25\u0e13\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e22\u0e30 \u0e01\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036651\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e04. \u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036651 \u0e1a\u0e08.\u0e17\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e04. \u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e19\u0e02\u0e31\u0e1a \u0e1a\u0e39\u0e21\u0e25\u0e34\u0e1f\u0e15\u0e4c \u0e42\u0e1f\u0e25\u0e4c\u0e04\u0e25\u0e34\u0e1f \u0e41\u0e1c\u0e48\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e15\u0e39\u0e49\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 529  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036707\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e49\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e1a\u0e39\u0e23\u0e1e\u0e32 3 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036707 \u0e1a\u0e08.\u0e2b\u0e49\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e1a\u0e39\u0e23\u0e1e\u0e32 3 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036715\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e27\u0e19\u0e17\u0e35\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036715 \u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e27\u0e19\u0e17\u0e35\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 42\/245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036723\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e40\u0e2b\u0e19\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35\u0e1e\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036723 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e40\u0e2b\u0e19\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35\u0e1e\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e42\u0e25\u0e2b\u0e30 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e44\u0e21\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e25\u0e2b\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 195\/78   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 103 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036731\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e34\u0e23\u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43309\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43309\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036731 \u0e1a\u0e08.\u0e16\u0e34\u0e23\u0e27\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 43309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 156\/120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036740\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14 \u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036740 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14 \u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46\u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 504\/588  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036758\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036758 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 222\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003736\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23789 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003736 \u0e1a\u0e08.\u0e19\u0e04\u0e23789 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e1a\u0e34\u0e49\u0e27\u0e2d\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e15\u0e36\u0e01\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0345569003174\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003174 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 226\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0403569003074\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e23\u0e23\u0e22\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003074 \u0e2b\u0e08.\u0e08\u0e23\u0e23\u0e22\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c 2569-07-10 5000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a o2o (online to offline) \u0e41\u0e25\u0e30 last mile delivery \u904b\u8f38\u30fb\u7269\u6d41 293  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001616\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22\u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001616 \u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22\u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 2569-07-10 5000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 171  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e2b\u0e19\u0e2d\u0e07\u0e2b\u0e34\u0e19\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e34\u0e1a\u0e32\u0e25\u0e14\u0e33\u0e23\u0e34 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0583569000121\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e1e\u0e35\u0e1e\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\",\"province_ja\":\"\u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\",\"search_text\":\"0583569000121 \u0e2b\u0e08.\u0e23\u0e1e\u0e35\u0e1e\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-10 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e30 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u5efa\u8a2d 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0635569001438\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e2d\u0e2b\u0e4c\u0e19\u0e1a\u0e32\u0e23\u0e4c\u0e19\u0e2a\u0e4c \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001438 \u0e1a\u0e08.\u0e08\u0e2d\u0e2b\u0e4c\u0e19\u0e1a\u0e32\u0e23\u0e4c\u0e19\u0e2a\u0e4c \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 46900 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0735569007028\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c  \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007028 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c  \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e3a\u0e4c\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 499\/1  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0835569012811\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e40\u0e25\u0e18 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012811 \u0e1a\u0e08.\u0e42\u0e04\u0e40\u0e25\u0e18 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 27\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010249\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e23\u0e1e\u0e1a \u0e41\u0e17\u0e23\u0e47\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010249 \u0e1a\u0e08.\u0e20\u0e32\u0e23\u0e1e\u0e1a \u0e41\u0e17\u0e23\u0e47\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e02\u0e19\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e02\u0e38\u0e14 \u0e40\u0e08\u0e32\u0e30 \u0e25\u0e2d\u0e01 \u0e04\u0e39 \u0e04\u0e25\u0e2d\u0e07 \u0e1a\u0e48\u0e2d\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e30\u0e19\u0e49\u0e33\u0e15\u0e48\u0e32\u0e07 \u0e46 \u5efa\u8a2d 41\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0925569000994\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e1f\u0e39 \u0e1f\u0e2d\u0e40\u0e23\u0e2a\u0e15\u0e49\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569000994 \u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e1f\u0e39 \u0e1f\u0e2d\u0e40\u0e23\u0e2a\u0e15\u0e49\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0925569001001\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e1f\u0e39 \u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e27\u0e31\u0e19 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001001 \u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e1f\u0e39 \u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e27\u0e31\u0e19 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0925569001010\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e49\u0e19\u0e20\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001010 \u0e1a\u0e08.\u0e1e\u0e49\u0e19\u0e20\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0105569129412\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e19\u0e17\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129412 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e19\u0e17\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d \u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 (work permit) \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 (visa) \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 \u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 128  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1935 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129552\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0a\u0e0d\u0e32 \u0e41\u0e27\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129552 \u0e1a\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0a\u0e0d\u0e32 \u0e41\u0e27\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 295\/109  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 119\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129650\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129650 \u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 738 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129692\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e21 \u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129692 \u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e21 \u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e15\u0e30\u0e01\u0e31\u0e48\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e42\u0e25\u0e2b\u0e30 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 499\/130  \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129722\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e04 \u0e42\u0e04-\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129722 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e04 \u0e42\u0e04-\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e27\u0e34\u0e17\u0e22\u0e38\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e38\u0e01\u0e23\u0e38\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e19\u0e02\u0e42\u0e21\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1c\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e2d\u0e01\u0e44\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e4a\u0e32\u0e0b\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e1e \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 59\/15  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 44 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129897\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e0b\u0e35\u0e27\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129897 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e0b\u0e35\u0e27\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 22\/434  \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129919\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129919 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e1a\u0e39\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129935\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e2a\u0e27\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e43\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79909\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79909\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129935 \u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e2a\u0e27\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19\u0e43\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 79909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e0a\u0e48\u0e48\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 91\/50  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129960\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e22\u0e27\u0e48\u0e42\u0e0b\u0e48\u0e27 \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129960 \u0e1a\u0e08.\u0e40\u0e22\u0e27\u0e48\u0e42\u0e0b\u0e48\u0e27 \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev) \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 719  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 23 \u0e42\u0e0b\u0e19 \u0e0b\u0e35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130119\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e17\u0e47\u0e2d\u0e1b\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130119 \u0e1a\u0e08.\u0e1a\u0e34\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e17\u0e47\u0e2d\u0e1b\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (digital platform) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 21\/129  \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e219 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130178\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e42\u0e01\u0e23 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130178 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e42\u0e01\u0e23 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 (\u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e01\u0e33\u0e25\u0e31\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e21\u0e14\u0e39\u0e25 (module-level power electronics (mlpe)) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118\/1  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130224\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e08\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130224 \u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e08\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 580  \u0e16\u0e19\u0e19\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130291\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130291 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 19\/55  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 97 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130305\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e35\u0e48\u0e44\u0e17\u0e49 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130305 \u0e1a\u0e08.\u0e25\u0e35\u0e48\u0e44\u0e17\u0e49 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 46411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e28\u0e29\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/53  \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130372\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32 \u0e21\u0e32\u0e23\u0e32\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130372 \u0e1a\u0e08.\u0e25\u0e32 \u0e21\u0e32\u0e23\u0e32\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 760\/124  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130453\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e23\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130453 \u0e1a\u0e08.\u0e44\u0e23\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 45102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 99\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130569\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130569 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 24  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 120 (\u0e40\u0e08\u0e49\u0e32\u0e04\u0e38\u0e13) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130593\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130593 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 168\/63  \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569025714\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e32\u0e15\u0e49\u0e32 \u0e04\u0e32\u0e2a\u0e0b\u0e32\u0e27\u0e48\u0e32\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10621\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10621\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025714 \u0e1a\u0e08.\u0e15\u0e32\u0e15\u0e49\u0e32 \u0e04\u0e32\u0e2a\u0e0b\u0e32\u0e27\u0e48\u0e32\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 10621 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u88fd\u9020 49\/128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025757\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e04\u0e42\u0e17\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e44\u0e19\u0e19\u0e4c \u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025757 \u0e1a\u0e08.\u0e2d\u0e2d\u0e04\u0e42\u0e17\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e44\u0e19\u0e19\u0e4c \u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95\/111  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e17\u0e23\u0e31\u0e2a\u0e15\u0e4c \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e2d\u0e49\u0e2d\u0e21\u0e40\u0e01\u0e23\u0e47\u0e141 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025889\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e25\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025889 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e25\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01  \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e38\u0e14\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 305\/111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025951\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e27\u0e31\u0e19 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025951 \u0e1a\u0e08.\u0e1a\u0e35 \u0e27\u0e31\u0e19 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 92\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025986\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025986 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a \u0e04\u0e33\u0e19\u0e27\u0e13 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23  \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e2d\u0e32\u0e17\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e39\u0e25\u0e25\u0e34\u0e48\u0e07\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c (cooling tower) \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e34\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c (chiller) \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e2d\u0e32\u0e04\u0e32\u0e23 (building automation system : bas) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23 (building management system : bms) \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e1e \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (cctv) \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e2d\u0e01 (access control) \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar photovoltaic system : solar pv) \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 (solar rooftop) \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar farm) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 (battery energy storage system : bess) \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station : ev charger) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 (energy management system : ems) \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021131\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e21\u0e28\u0e31\u0e2a\u0e15\u0e23\u0e32\u0e40\u0e17\u0e1e \u0e40\u0e40\u0e2d\u0e17\u0e40\u0e2a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021131 \u0e1a\u0e08.\u0e04\u0e21\u0e28\u0e31\u0e2a\u0e15\u0e23\u0e32\u0e40\u0e17\u0e1e \u0e40\u0e40\u0e2d\u0e17\u0e40\u0e2a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e33 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u4e0d\u52d5\u7523 322  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e3531 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021328\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021328 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 46\/393  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0165569001572\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e40\u0e1f\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001572 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e40\u0e1f\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036103\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e48\u0e2d\u0e36\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036103 \u0e1a\u0e08.\u0e41\u0e0b\u0e48\u0e2d\u0e36\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 5\/5  \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e36\u0e07\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036197\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52213\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52213\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036197 \u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 52213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e08\u0e2d\u0e14 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 100\/384  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e323 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 18 \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e32\u0e07\u0e28\u0e34\u0e25\u0e32 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036251\",\"name_th\":\"\u0e1a\u0e08.\u0e0a \u0e40\u0e15\u0e47\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036251 \u0e1a\u0e08.\u0e0a \u0e40\u0e15\u0e47\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 249  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036278\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e28\u0e34\u0e23\u0e34 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036278 \u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e28\u0e34\u0e23\u0e34 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e40\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e17\u0e33\u0e14\u0e49\u0e27\u0e22\u0e17\u0e2d\u0e07 \u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e40\u0e40\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e48\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e40\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e40\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e48\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/2-3,46\/4  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036316\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e39 \u0e40\u0e0b\u0e35\u0e22\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036316 \u0e1a\u0e08.\u0e0a\u0e39 \u0e40\u0e0b\u0e35\u0e22\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23  \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e35\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 351\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036332\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036332 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23  \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e08\u0e35\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e34\u0e21\u0e0a\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e0a\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e0a\u0e32 \u0e0a\u0e38\u0e14\u0e0a\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 331\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036383\",\"name_th\":\"\u0e1a\u0e08.331 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036383 \u0e1a\u0e08.331 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 88\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036448\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e40\u0e0b\u0e35\u0e22\u0e07 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036448 \u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e40\u0e0b\u0e35\u0e22\u0e07 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35\u0e48\u0e49 \u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e14\u0e37\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036472\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e40\u0e1a\u0e2a\u0e17\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036472 \u0e1a\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e40\u0e1a\u0e2a\u0e17\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 356\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0325569001198\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e27\u0e31\u0e15 \u0e01\u0e23\u0e35\u0e19\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001198 \u0e1a\u0e08.\u0e20\u0e27\u0e31\u0e15 \u0e01\u0e23\u0e35\u0e19\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32(ev charging station)\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 145  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0363569000874\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e23\u0e31\u0e0a \u0e27\u0e31\u0e2a\u0e14\u0e38\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000874 \u0e2b\u0e08.\u0e27\u0e34\u0e23\u0e31\u0e0a \u0e27\u0e31\u0e2a\u0e14\u0e38 2569-07-09 5000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 196  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0403569003031\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e2d\u0e2a\u0e15\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003031 \u0e2b\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e2d\u0e2a\u0e15\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-09 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 234\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e01\u0e48\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006563\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e0b\u0e32\u0e42\u0e14\u0e30 \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006563 \u0e1a\u0e08.\u0e2d\u0e32\u0e0b\u0e32\u0e42\u0e14\u0e30 \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e22\u0e32\u0e01\u0e34\u0e19\u0e34\u0e01\u0e38 \u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 190\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006580\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e40\u0e17\u0e25 \u0e40\u0e1e\u0e47\u0e17 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31009\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31009\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006580 \u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e40\u0e17\u0e25 \u0e40\u0e1e\u0e47\u0e17 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 31009 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e15\u0e39\u0e49 \u0e40\u0e15\u0e35\u0e22\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u88fd\u9020 433\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003548\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e44\u0e2d\u0e1e\u0e35 \u0e04\u0e25\u0e31\u0e1a \u0e2d\u0e38\u0e14\u0e23  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003548 \u0e1a\u0e08.\u0e27\u0e35\u0e44\u0e2d\u0e1e\u0e35 \u0e04\u0e25\u0e31\u0e1a \u0e2d\u0e38\u0e14\u0e23  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 549  \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e28\u0e23\u0e35 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000750\",\"name_th\":\"\u0e2b\u0e08.\u0e15.\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e072026\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000750 \u0e2b\u0e08.\u0e15.\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e072026 2569-07-09 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 201  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0505569015545\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015545 \u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 400  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015553\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e27\u0e34\u0e19 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015553 \u0e1a\u0e08.\u0e18\u0e32\u0e27\u0e34\u0e19 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 175\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015570\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e27\u0e25\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015570 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e27\u0e25\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 (operation and maintenance) \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u5efa\u8a2d 175\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0655569002213\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e23\u0e27\u0e34\u0e0a.546 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002213 \u0e1a\u0e08.\u0e27\u0e23\u0e27\u0e34\u0e0a.546 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0835569012675\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e25\u0e48\u0e32 \u0e23\u0e32\u0e44\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012675 \u0e1a\u0e08.\u0e42\u0e21\u0e25\u0e48\u0e32 \u0e23\u0e32\u0e44\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0925569000986\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e0a\u0e31\u0e22\u0e42\u0e25\u0e2b\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569000986 \u0e1a\u0e08.\u0e15\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e0a\u0e31\u0e22\u0e42\u0e25\u0e2b\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 5000000 47522 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149\/2-149\/3  \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e23\u0e31\u0e29\u0e0e\u0e32 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0105569128688\",\"name_th\":\"\u0e1a\u0e08.24 \u0e1f\u0e39\u0e49\u0e14 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128688 \u0e1a\u0e08.24 \u0e1f\u0e39\u0e49\u0e14 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e04\u0e32\u0e40\u0e1f\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 41\/1  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 21 \u0e41\u0e22\u0e01 2-1 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128696\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e27\u0e25 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e1a\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128696 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e27\u0e25 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e1a\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e01\u0e32\u0e23  \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u88fd\u9020 78\/8  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128971\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e08\u0e35\u0e1e\u0e35 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e01\u0e23\u0e35\u0e19 \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128971 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e08\u0e35\u0e1e\u0e35 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e01\u0e23\u0e35\u0e19 \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 10\/42  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e17\u0e23\u0e19\u0e14\u0e35\u0e49  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a6 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1a \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 13 (\u0e41\u0e2a\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129269\",\"name_th\":\"\u0e1a\u0e08.103 \u0e2d\u0e2d\u0e42\u0e15\u0e44\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129269 \u0e1a\u0e08.103 \u0e2d\u0e2d\u0e42\u0e15\u0e44\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 45302 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 394,396,398  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129382\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e40\u0e08\u0e19 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129382 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e40\u0e08\u0e19 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 435 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022570\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e25\u0e35\u0e48 \u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022570 \u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e25\u0e35\u0e48 \u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e04\u0e37\u0e19\u0e20\u0e32\u0e29\u0e35\u0e40\u0e07\u0e34\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 \u0e17\u0e19\u0e32\u0e22\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 168\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025552\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e21\u0e01\u0e49\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025552 \u0e1a\u0e08.\u0e27\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e21\u0e01\u0e49\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 9\/253  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021000\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e0b\u0e35\u0e0b\u0e31\u0e19\u0e2a\u0e4c \u0e2d\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021000 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e0b\u0e35\u0e0b\u0e31\u0e19\u0e2a\u0e4c \u0e2d\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e38\u0e4b\u0e22 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 (\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e2a\u0e32\u0e23\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e49\u0e32\u0e21) \u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51\/319  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569035948\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035948 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 245\/108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036006\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e39\u0e27\u0e32 \u0e0a\u0e39\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64999\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64999\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036006 \u0e1a\u0e08.\u0e0a\u0e39\u0e27\u0e32 \u0e0a\u0e39\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 64999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e31\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u91d1\u878d\u30fb\u4fdd\u967a 10\/251  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036057\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e04. \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036057 \u0e1a\u0e08.\u0e17\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e04. \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 77109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19\u0e43\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e42\u0e22\u0e18\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 529  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036065\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e23\u0e35\u0e42\u0e22\u0e04\u0e30 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036065 \u0e1a\u0e08.\u0e1f\u0e23\u0e35\u0e42\u0e22\u0e04\u0e30 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e42\u0e22\u0e04\u0e30 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e1d\u0e19 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e22\u0e04\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 197\/21  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19-\u0e41\u0e15\u0e07\u0e2d\u0e48\u0e2d\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036073\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e42\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036073 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e42\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 273\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0235569000401\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e48\u0e07\u0e21\u0e35\u0e0a\u0e31\u0e22\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0235569000401 \u0e1a\u0e08.\u0e21\u0e34\u0e48\u0e07\u0e21\u0e35\u0e0a\u0e31\u0e22\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 223  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0313569000998\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c 2026\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569000998 \u0e2b\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c 2026 2569-07-08 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0393569000335\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1f.\u0e1f\u0e34\u0e27\u0e2a\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000335 \u0e2b\u0e08.\u0e40\u0e2d\u0e1f.\u0e1f\u0e34\u0e27\u0e2a\u0e4c 2569-07-08 5000000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u904b\u8f38\u30fb\u7269\u6d41 269  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0405569006521\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e48\u0e32 \u0e40\u0e04\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a1998 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006521 \u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e48\u0e32 \u0e40\u0e04\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a1998 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003521\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003521 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e44\u0e02\u0e04\u0e27\u0e07 \u0e04\u0e49\u0e2d\u0e19 \u0e1b\u0e23\u0e30\u0e41\u0e08 \u0e15\u0e25\u0e31\u0e1a\u0e40\u0e21\u0e15\u0e23 \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2a\u0e01\u0e23\u0e39 \u0e19\u0e2d\u0e15 \u0e1e\u0e38\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e2b\u0e21\u0e27\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e02\u0e48\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 355\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0473569000890\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e2d\u0e40\u0e23\u0e47\u0e01 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000890 \u0e2b\u0e08.\u0e1f\u0e2d\u0e40\u0e23\u0e47\u0e01 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c 2569-07-08 5000000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0483569000512\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d.\u0e27\u0e32\u0e22.\u0e40\u0e2d. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000512 \u0e2b\u0e08.\u0e40\u0e2d.\u0e27\u0e32\u0e22.\u0e40\u0e2d. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-08 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0505569015430\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015430 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 135\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0803569000918\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e27\u0e31\u0e0d\u0e24\u0e17\u0e31\u0e22 \u0e04\u0e27\u0e35\u0e19 \u0e2d\u0e4a\u0e2d\u0e1f\u0e1f\u0e23\u0e38\u0e4a\u0e15\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000918 \u0e2b\u0e08.\u0e02\u0e27\u0e31\u0e0d\u0e24\u0e17\u0e31\u0e22 \u0e04\u0e27\u0e35\u0e19 \u0e2d\u0e4a\u0e2d\u0e1f\u0e1f\u0e23\u0e38\u0e4a\u0e15 2569-07-08 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e21\u0e31\u0e07\u0e04\u0e38\u0e14\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0905569005465\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e25\u0e2d\u0e08\u0e34\u0e01 \u0e17\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005465 \u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e25\u0e2d\u0e08\u0e34\u0e01 \u0e17\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 469\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0935569000790\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e15\u0e38\u0e0d\u0e1e\u0e31\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01462\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01462\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000790 \u0e1a\u0e08.\u0e08\u0e15\u0e38\u0e0d\u0e1e\u0e31\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 5000000 01462 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u8fb2\u6797\u6c34\u7523 157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0105569127720\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e22\u0e23\u0e32 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127720 \u0e1a\u0e08.\u0e44\u0e2d\u0e22\u0e23\u0e32 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 16  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e32\u0e2a\u0e32\u0e22 1 \u0e0b\u0e2d\u0e22 45 \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127754\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e30 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127754 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e30 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 71102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 80\/1  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 80 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127835\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e0a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e32\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127835 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e0a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e32\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e2b\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u533b\u7642\u30fb\u798f\u7949 8\/888  \u0e16\u0e19\u0e19\u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127894\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127894 \u0e1a\u0e08.\u0e04\u0e34\u0e27 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 8  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128068\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128068 \u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 727\/50  \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128181\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e2d\u0e2a\u0e40\u0e0b\u0e19 \u0e40\u0e1f\u0e23\u0e19\u0e0b\u0e34\u0e1b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128181 \u0e1a\u0e08.\u0e2e\u0e2d\u0e2a\u0e40\u0e0b\u0e19 \u0e40\u0e1f\u0e23\u0e19\u0e0b\u0e34\u0e1b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 62 \u0e41\u0e22\u0e01 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128211\",\"name_th\":\"\u0e1a\u0e08. \u0e1a\u0e2d\u0e2a \u0e40\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128211 \u0e1a\u0e08. \u0e1a\u0e2d\u0e2a \u0e40\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 96309 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e37\u0e48\u0e19\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13\u0e2d\u0e32\u0e22\u0e38 \u0e27\u0e35\u0e0b\u0e48\u0e32 ltr \u0e27\u0e35\u0e0b\u0e48\u0e32 elite \u0e27\u0e48\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 1179  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 6 \u0e0a\u0e31\u0e49\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128238\",\"name_th\":\"\u0e1a\u0e08.  \u0e40\u0e2d \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e2a \u0e40\u0e04 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128238 \u0e1a\u0e08.  \u0e40\u0e2d \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e2a \u0e40\u0e04 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e2a\u0e31\u0e13\u0e0d\u0e32\u0e13 \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e41\u0e27\u0e23\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e08\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25 \u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e1f\u0e15\u0e34\u0e04 \u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 1179  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 6 \u0e0a\u0e31\u0e49\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128262\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e40\u0e09\u0e34\u0e07 \u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22210\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22210\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128262 \u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e40\u0e09\u0e34\u0e07 \u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 22210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 15  \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128475\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e2d\u0e17 \u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128475 \u0e1a\u0e08.\u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e2d\u0e17 \u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 99\/67  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128513\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e40\u0e28\u0e29\u0e27\u0e07\u0e29\u0e4c 1301 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128513 \u0e1a\u0e08.\u0e27\u0e34\u0e40\u0e28\u0e29\u0e27\u0e07\u0e29\u0e4c 1301 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 70100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 8  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022405\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022405 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e01\u0e17\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 234\/128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022430\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e1e\u0e35 \u0e0b\u0e35\u0e40\u0e25\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022430 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e1e\u0e35 \u0e0b\u0e35\u0e40\u0e25\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e2d\u0e1a \u0e40\u0e2a\u0e35\u0e22\u0e21 \u0e1e\u0e25\u0e31\u0e48\u0e27 \u0e04\u0e23\u0e32\u0e14 \u0e1a\u0e31\u0e27\u0e23\u0e14\u0e19\u0e49\u0e33 \u0e2a\u0e32\u0e22\u0e22\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e48\u0e19\u0e22\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33 \u0e17\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33 \u0e16\u0e31\u0e07\u0e1e\u0e48\u0e19\u0e2a\u0e32\u0e23 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01 \u0e14\u0e34\u0e19\u0e1b\u0e25\u0e39\u0e01 \u0e1b\u0e38\u0e4b\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/126  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e1a\u0e32\u0e07\u0e19\u0e322 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022464\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2b\u0e31\u0e27 \u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e34\u0e19\u0e42\u0e14\u0e27\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022464 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2b\u0e31\u0e27 \u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e34\u0e19\u0e42\u0e14\u0e27\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e22\u0e39\u0e1e\u0e35\u0e27\u0e35\u0e0b\u0e35 (upvc) \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1f \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 444\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022472\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35 \u0e2d\u0e35-\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022472 \u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35 \u0e2d\u0e35-\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/66   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a105 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 23 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022499\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e34\u0e07\u0e2d\u0e31\u0e19 \u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022499 \u0e1a\u0e08.\u0e40\u0e2b\u0e34\u0e07\u0e2d\u0e31\u0e19 \u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e04\u0e37\u0e19\u0e20\u0e32\u0e29\u0e35\u0e40\u0e07\u0e34\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 \u0e17\u0e19\u0e32\u0e22\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 121\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025391\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e42\u0e2d.\u0e1e\u0e35.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d   \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025391 \u0e1a\u0e08.\u0e1e\u0e35.\u0e42\u0e2d.\u0e1e\u0e35.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d   \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 89\/994  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025404\",\"name_th\":\"\u0e1a\u0e08.\u0e1d\u0e19\u0e17\u0e2d\u0e07 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025404 \u0e1a\u0e08.\u0e1d\u0e19\u0e17\u0e2d\u0e07 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 62\/41  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32 25 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025463\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e25\u0e49\u0e33 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025463 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e25\u0e49\u0e33 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e01\u0e48\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e02\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2b\u0e23\u0e37\u0e2d \u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 998\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0175569000444\",\"name_th\":\"\u0e1a\u0e08.\u0e09.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000444 \u0e1a\u0e08.\u0e09.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e23\u0e49\u0e32\u0e19\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0175569000452\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000452 \u0e1a\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01  \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035824\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e0b\u0e35 \u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035824 \u0e1a\u0e08.\u0e2b\u0e07\u0e0b\u0e35 \u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e25\u0e07\u0e17\u0e38\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 9\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009025\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e44\u0e17\u0e48 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009025 \u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e44\u0e17\u0e48 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e04\u0e33\u0e19\u0e27\u0e13 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 998\/103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009068\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81292\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81292\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009068 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 81292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e25\u0e49\u0e32\u0e07\u0e1a\u0e48\u0e2d\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e25\u0e34\u0e15 \u0e25\u0e49\u0e32\u0e07\u0e16\u0e31\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e01\u0e23\u0e2d\u0e07\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 29\/15  \u0e0b\u0e2d\u0e22 \u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e16\u0e19\u0e19\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e22\u0e2d\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015286\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015286 \u0e1a\u0e08.\u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c  \u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 222\/484  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015324\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015324 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e1a\u0e49\u0e32\u0e19\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e44\u0e21\u0e49\u0e01\u0e27\u0e32\u0e14 \u0e44\u0e21\u0e49\u0e16\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e20\u0e32\u0e0a\u0e19\u0e30 \u0e43\u0e19\u0e04\u0e23\u0e31\u0e27 \u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07\u0e02\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e34\u0e0a\u0e0a\u0e39 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49  \u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e02\u0e48\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9809\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015341\",\"name_th\":\"\u0e1a\u0e08.\u0e0c\u0e32\u0e23\u0e4c\u0e21 1988 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015341 \u0e1a\u0e08.\u0e0c\u0e32\u0e23\u0e4c\u0e21 1988 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004373\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004373 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e25\u0e32\u0e19\u0e01\u0e32\u0e07\u0e40\u0e15\u0e47\u0e19\u0e17\u0e4c \u0e41\u0e04\u0e21\u0e1b\u0e4c\u0e1b\u0e34\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0725569002051\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e19\u0e15\u0e23\u0e32 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002051 \u0e1a\u0e08.\u0e21\u0e19\u0e15\u0e23\u0e32 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e1e\u0e23\u0e21 \u0e42\u0e04\u0e21\u0e44\u0e1f \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0765569001445\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e27\u0e31\u0e0d \u0e2d\u0e35\u0e27\u0e35\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001445 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e27\u0e31\u0e0d \u0e2d\u0e35\u0e27\u0e35\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charger) \u0e23\u0e30\u0e1a\u0e1a\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e14\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 146\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0835569012578\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012578 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 45203 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e1a\u0e23\u0e01 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e15\u0e32\u0e21\u0e23\u0e30\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012586\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e32 \u0e42\u0e01\u0e23\u0e17 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"39000\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"39000\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012586 \u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e32 \u0e42\u0e01\u0e23\u0e17 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 39000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e01\u0e33\u0e08\u0e31\u0e14 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e38\u0e4b\u0e22\u0e2b\u0e21\u0e31\u0e01 (aerobic degestion) \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 55\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010125\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e35\u0e22 \u0e27\u0e19\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010125 \u0e1a\u0e08.\u0e40\u0e27\u0e35\u0e22 \u0e27\u0e19\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e25\u0e30 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e22\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 24\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005449\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005449 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 184  \u0e0b\u0e2d\u0e22 1 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0955569000544\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e17\u0e22\u0e32 \u0e23\u0e35\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000544 \u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e17\u0e22\u0e32 \u0e23\u0e35\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01\u0e04\u0e39 \u0e04\u0e25\u0e2d\u0e07 \u0e2b\u0e19\u0e2d\u0e07 \u0e1a\u0e36\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u5efa\u8a2d 36\/4  \u0e16\u0e19\u0e19\u0e44\u0e0a\u0e22\u0e08\u0e23\u0e31\u0e2a 1 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569126910\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04\u0e2a\u0e1e\u0e32\u0e23\u0e4c\u0e04\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126910 \u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04\u0e2a\u0e1e\u0e32\u0e23\u0e4c\u0e04\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 610\/4  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127053\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e2a\u0e4c\u0e15\u0e31\u0e19 \u0e40\u0e2d\u0e04\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127053 \u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e2a\u0e4c\u0e15\u0e31\u0e19 \u0e40\u0e2d\u0e04\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 85491 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e0a\u0e47\u0e2d\u0e1b\u0e40\u0e08\u0e32\u0e30\u0e25\u0e36\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e30\u0e41\u0e19\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e32\u0e01\u0e25\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19   igcse, a-level, ib, \u0e2b\u0e23\u0e37\u0e2d ap \u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e41\u0e25\u0e30\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u6559\u80b2 28\/109  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 28 chidlom \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127118\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e23\u0e32\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127118 \u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e23\u0e32\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 184\/11  \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127231\",\"name_th\":\"\u0e1a\u0e08. \u0e17\u0e35\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74909\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74909\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127231 \u0e1a\u0e08. \u0e17\u0e35\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 74909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 41\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 5 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127533\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127533 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 56102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b, \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 41\/123  \u0e0b\u0e2d\u0e22 \u0e44\u0e21\u0e15\u0e23\u0e35\u0e08\u0e34\u0e15 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127550\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e27\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47512\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47512\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127550 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e27\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 47512 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 727\/50  \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022201\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e27\u0e30\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022201 \u0e1a\u0e08.\u0e41\u0e27\u0e30\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120\/460  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025030\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e08\u0e35\u0e2d\u0e35\u0e17\u0e35) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025030 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e08\u0e35\u0e2d\u0e35\u0e17\u0e35) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 2\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025111\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025111 \u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e22\u0e34\u0e21 \u0e42\u0e22\u0e04\u0e30 \u0e1e\u0e34\u0e25\u0e32\u0e17\u0e34\u0e2a \u0e41\u0e2d\u0e42\u0e23\u0e1a\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 126\/794  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025137\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025137 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u533b\u7642\u30fb\u798f\u7949 110\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025161\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e23\u0e0b\u0e34\u0e48\u0e07 \u0e2d\u0e34\u0e04\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025161 \u0e1a\u0e08.\u0e44\u0e23\u0e0b\u0e34\u0e48\u0e07 \u0e2d\u0e34\u0e04\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 82199 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e48\u0e19\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e48\u0e19\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e37\u0e48\u0e19\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 49\/224  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 \u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035409\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e41\u0e1b\u0e14\u0e41\u0e1b\u0e14\u0e41\u0e1b\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035409 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e41\u0e1b\u0e14\u0e41\u0e1b\u0e14\u0e41\u0e1b\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035433\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e27\u0e48\u0e22 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035433 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e27\u0e48\u0e22 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 41001 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 (hvac) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035611\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035611 \u0e1a\u0e08.\u0e2e\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e28\u0e29\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 106\/53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003621\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e21\u0e25\u0e4c\u0e2a \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003621 \u0e1a\u0e08.\u0e44\u0e21\u0e25\u0e4c\u0e2a \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 89\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0475569001421\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001421 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 23951 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 458  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015227\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015227 \u0e1a\u0e08.\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 (\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e19\u0e32\u0e07\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17) \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e37\u0e48\u0e19\u0e40\u0e23\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001595\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e25\u0e32\u0e07\u0e04\u0e4c\u0e40\u0e21\u0e47\u0e17\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001595 \u0e1a\u0e08.\u0e40\u0e02\u0e25\u0e32\u0e07\u0e04\u0e4c\u0e40\u0e21\u0e47\u0e17\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 46639 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 247\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0655569002116\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e44\u0e1e\u0e25\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002116 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e44\u0e1e\u0e25\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 286  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0715569002476\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e1a\u0e34\u0e0b \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002476 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e1a\u0e34\u0e0b \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e4d\u0e32\u0e1e\u0e27\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e4d\u0e32\u0e2d\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e07\u0e42\u0e09\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e44\u0e2d\u0e17\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0835569012527\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e32 \u0e40\u0e23\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012527 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e32 \u0e40\u0e23\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e1a\u0e32\u0e23\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e2d\u0e37\u0e48\u0e19\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 35\/22  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 200 \u0e1b\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010087\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e2a\u0e21\u0e38\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010087 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e2a\u0e21\u0e38\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 40\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005341\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e44\u0e25\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005341 \u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e44\u0e25\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 5000000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e35 \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95\/233  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e16\u0e19\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e3850(\u0e2d\u0e33\u0e44\u0e1e\u0e0a\u0e31\u0e22\u0e42\u0e0a\u0e04\u0e2d\u0e38\u0e17\u0e34\u0e28) \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569126715\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e32\u0e40\u0e17\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126715 \u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e32\u0e40\u0e17\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 5000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e48\u0e19\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e44\u0e2a\u0e49\u0e01\u0e23\u0e2d\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e19\u0e49\u0e33 \u5efa\u8a2d 77\/29  \u0e16\u0e19\u0e19\u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126731\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e32\u0e44\u0e1a\u0e15\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126731 \u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e32\u0e44\u0e1a\u0e15\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 737 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e15\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0305569006955\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c\u0e40\u0e25\u0e2a \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006955 \u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c\u0e40\u0e25\u0e2a \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 5000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006963\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e24\u0e29\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e25\u0e19\u0e14\u0e4c\u0e2a\u0e40\u0e04\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006963 \u0e1a\u0e08.\u0e01\u0e24\u0e29\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e25\u0e19\u0e14\u0e4c\u0e2a\u0e40\u0e04\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0483569000491\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e021989\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000491 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e021989 2569-07-05 5000000 47912 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\/\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14  \u0e0b\u0e2d\u0e22 \u0e2a\u0e27\u0e48\u0e32\u0e07\u0e19\u0e20\u0e32 \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e19\u0e04\u0e23 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0105569126634\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19\u0e19\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126634 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19\u0e19\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 5000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e30\u0e2a\u0e21 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/34  \u0e0b\u0e2d\u0e22 \u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022138\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022138 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 178\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569035328\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e42\u0e23\u0e48 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035328 \u0e1a\u0e08.\u0e1f\u0e35\u0e42\u0e23\u0e48 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 5000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1b\u0e48\u0e32\u0e02\u0e27\u0e14 (blow molding machine), \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e09\u0e35\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 (injection molding machine), \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1b\u0e48\u0e32\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e27\u0e07 (extrusion blow molding machine), \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e34\u0e14\u0e09\u0e25\u0e32\u0e01, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e48\u0e2d\u0e1f\u0e34\u0e25\u0e4c\u0e21, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\/\u0e23\u0e2b\u0e31\u0e2a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e40\u0e23\u0e35\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (palletizer), \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33 ro (reverse osmosis), \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e19\u0e49\u0e33\u0e40\u0e22\u0e47\u0e19 (chiller), \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e25\u0e21\u0e41\u0e2b\u0e49\u0e07 (air dryer), \u0e16\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e25\u0e21, \u0e2b\u0e2d\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e22\u0e47\u0e19 (cooling tower), \u0e16\u0e31\u0e07\u0e19\u0e49\u0e33\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a, \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07, \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32, \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 plc \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 889\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0405569006431\",\"name_th\":\"\u0e1a\u0e08.27 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006431 \u0e1a\u0e08.27 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001405\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e42\u0e2e\u0e40\u0e15\u0e47\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001405 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e42\u0e2e\u0e40\u0e15\u0e47\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015189\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c\u0e1f\u0e34\u0e01\u0e0b\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015189 \u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c\u0e1f\u0e34\u0e01\u0e0b\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 5000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569125786\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e40\u0e17\u0e34\u0e25 \u0e04\u0e25\u0e35\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125786 \u0e1a\u0e08.\u0e42\u0e17\u0e40\u0e17\u0e34\u0e25 \u0e04\u0e25\u0e35\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 289  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1935 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125808\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e1e\u0e34\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64922\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64922\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125808 \u0e1a\u0e08.\u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e1e\u0e34\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 64922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e22\u0e48\u0e2d\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e33\u0e01\u0e31\u0e1a (\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e42\u0e01\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u91d1\u878d\u30fb\u4fdd\u967a 252\/115  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e20\u0e31\u0e17\u0e23 \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 22 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125816\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e40\u0e17\u0e34\u0e25 \u0e2d\u0e34\u0e19\u0e42\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125816 \u0e1a\u0e08.\u0e42\u0e17\u0e40\u0e17\u0e34\u0e25 \u0e2d\u0e34\u0e19\u0e42\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 289  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125832\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e23\u0e38\u0e15\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125832 \u0e1a\u0e08.\u0e1f\u0e23\u0e38\u0e15\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 400\/131  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c 2 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125867\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64992\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64992\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125867 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 64992 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e2b\u0e19\u0e35\u0e49 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e19 \u0e2a\u0e01\u0e38\u0e25\u0e40\u0e07\u0e34\u0e19 \u0e2a\u0e01\u0e38\u0e25\u0e40\u0e07\u0e34\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c (commodities) \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e32\u0e04\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e01\u0e4a\u0e32\u0e0b\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e34\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e49\u0e32\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e21\u0e17\u0e38\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e2d\u0e31\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u91d1\u878d\u30fb\u4fdd\u967a 36  \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 4 \u0e41\u0e22\u0e01 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125956\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e27\u0e31\u0e48\u0e07\u0e0b\u0e27\u0e35\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46422\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46422\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125956 \u0e1a\u0e08.\u0e0a\u0e27\u0e31\u0e48\u0e07\u0e0b\u0e27\u0e35\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46422 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e42\u0e04\u0e21\u0e44\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/4  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e22\u0e39\u0e19\u0e34\u0e15 \u0e1a\u0e35 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126014\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126014 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e23\u0e32\u0e04\u0e32 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 33\/18  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126154\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46433\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46433\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126154 \u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46433 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/266  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021964\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e17\u0e35. \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0115569021964 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e17\u0e35. \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0115569021972\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021972 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 178\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021981\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35. \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021981 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35. \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021999\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c 1950 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021999 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c 1950 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022006\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022006 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 165\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022014\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35. \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022014 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35. \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 165\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022022\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39.\u0e14\u0e35.\u0e40\u0e2d\u0e1f \u0e0b\u0e35\u0e0b\u0e31\u0e19 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022022 \u0e1a\u0e08.\u0e22\u0e39.\u0e14\u0e35.\u0e40\u0e2d\u0e1f \u0e0b\u0e35\u0e0b\u0e31\u0e19 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022049\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e08\u0e39 \u0e1a\u0e34\u0e27\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022049 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e08\u0e39 \u0e1a\u0e34\u0e27\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 47525 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e40\u0e1a\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 194  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024785\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e21\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024785 \u0e1a\u0e08.\u0e44\u0e21\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e28\u0e36\u0e01\u0e29\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 161\/10  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e0b\u0e34\u0e15\u0e35\u0e49\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 - \u0e19\u0e04\u0e23\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024793\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e39\u0e17\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024793 \u0e1a\u0e08.\u0e23\u0e39\u0e17\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2d\u0e17\u0e35 (it)  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2a\u0e32\u0e22\u0e41\u0e25\u0e19 (lan cable) \u0e2a\u0e27\u0e34\u0e15\u0e0a\u0e4c (switch) \u0e40\u0e23\u0e32\u0e40\u0e15\u0e2d\u0e23\u0e4c (router) \u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 (modem)  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 (access point) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 159\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024874\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e071998 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024874 \u0e1a\u0e08.\u0e40\u0e04 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e071998 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 65\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020569\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e38\u0e2c\u0e32 \u0e1f\u0e32\u0e23\u0e4c\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21002\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21002\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020569 \u0e1a\u0e08.\u0e08\u0e38\u0e2c\u0e32 \u0e1f\u0e32\u0e23\u0e4c\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 21002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u88fd\u9020 6\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020607\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e09\u0e34\u0e07\u0e0b\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020607 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e09\u0e34\u0e07\u0e0b\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e32\u0e44\u0e1f\u0e16\u0e19\u0e19 \u0e40\u0e2a\u0e32\u0e44\u0e1f\u0e16\u0e19\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar street light) \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 70\/342  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020615\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e0b\u0e34\u0e07\u0e15\u0e4b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020615 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e0b\u0e34\u0e07\u0e15\u0e4b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e1c\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c (solar cell) \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5efa\u8a2d 70\/342  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569035140\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35. \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035140 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35. \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035158\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e17 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035158 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e17 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 361\/105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035263\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035263 \u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 43210 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u5efa\u8a2d 88\/7 , 88\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035301\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a. \u0e0b\u0e35\u0e0b\u0e31\u0e19 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035301 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a. \u0e0b\u0e35\u0e0b\u0e31\u0e19 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0465569000832\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2a\u0e34\u0e29\u0e10\u0e4c \u0e44\u0e1a\u0e42\u0e2d\u0e41\u0e21\u0e2a 89 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000832 \u0e1a\u0e08.\u0e1e\u0e2a\u0e34\u0e29\u0e10\u0e4c \u0e44\u0e1a\u0e42\u0e2d\u0e41\u0e21\u0e2a 89 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32\u0e44\u0e21\u0e49\u0e1f\u0e37\u0e19\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e31\u0e1a \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e22\u0e30\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e02\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0485569000867\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e14\u0e32\u0e19\u0e04\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000867 \u0e1a\u0e08.\u0e23\u0e14\u0e32\u0e19\u0e04\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u5bbf\u6cca\u30fb\u98f2\u98df 54  \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21-\u0e18\u0e32\u0e15\u0e38\u0e1e\u0e19\u0e21 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0575569004306\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c 988 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004306 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c 988 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 244  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001461\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e48\u0e2d\u0e40\u0e07\u0e34\u0e19\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001461 \u0e2b\u0e08.\u0e1a\u0e48\u0e2d\u0e40\u0e07\u0e34\u0e19\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-03 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11  \u0e16\u0e19\u0e19\u0e1a\u0e48\u0e2d\u0e40\u0e07\u0e34\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569001918\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e2a\u0e35\u0e2a\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c 6 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10611\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10611\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001918 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e2a\u0e35\u0e2a\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c 6 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 10611 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e2a\u0e35\u0e02\u0e49\u0e32\u0e27 \u0e01\u0e32\u0e23\u0e2a\u0e35\u0e02\u0e49\u0e32\u0e27 \u88fd\u9020 99\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0705569003057\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e04\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003057 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e04\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e19\u0e49\u0e33\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 292\/84  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006731\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e44\u0e04 \u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22291\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22291\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006731 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e44\u0e04 \u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 22291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e16\u0e49\u0e27\u0e22\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e01\u0e49\u0e27\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e25\u0e2d\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e0a\u0e49\u0e2d\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 131\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007001\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28160\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28160\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007001 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 28160 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u88fd\u9020 99\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007028\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e17\u0e39\u0e19\u0e32 \u0e42\u0e04\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007028 \u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e17\u0e39\u0e19\u0e32 \u0e42\u0e04\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/237-238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569012462\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e42\u0e04\u0e48\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012462 \u0e1a\u0e08.\u0e42\u0e04\u0e42\u0e04\u0e48\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 5000000 68101 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e41\u0e22\u0e01\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1a\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 111\/469  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e27\u0e34\u0e0a 3 \u0e41\u0e2d\u0e17 \u0e1b\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569125051\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e02\u0e27\u0e31\u0e0d \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125051 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e02\u0e27\u0e31\u0e0d \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e44\u0e21\u0e49\u0e01\u0e27\u0e32\u0e14 \u0e44\u0e21\u0e49\u0e16\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e41\u0e1b\u0e23\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e16\u0e31\u0e07\u0e19\u0e49\u0e33 \u0e1f\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e1c\u0e49\u0e32\u0e40\u0e0a\u0e47\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e22\u0e32\u0e07 \u0e16\u0e38\u0e07\u0e02\u0e22\u0e30 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e08\u0e32\u0e19 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e16\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e40\u0e0a\u0e47\u0e14\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e20\u0e32\u0e0a\u0e19\u0e30\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e32\u0e19 \u0e0a\u0e32\u0e21 \u0e41\u0e01\u0e49\u0e27 \u0e0a\u0e49\u0e2d\u0e19\u0e2a\u0e49\u0e2d\u0e21 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e2d\u0e07 \u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07  \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 102\/3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125131\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e1a\u0e35\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e32\u0e2d\u0e31\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125131 \u0e1a\u0e08.\u0e19\u0e32\u0e1a\u0e35\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e32\u0e2d\u0e31\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27112(\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125191\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e25\u0e32 \u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e1f\u0e2d\u0e22\u0e25\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24201\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24201\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125191 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e25\u0e32 \u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e1f\u0e2d\u0e22\u0e25\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 24201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07, \u0e41\u0e16\u0e1a\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25\u0e0a\u0e19\u0e34\u0e14\u0e21\u0e35\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e23\u0e1a\u0e01\u0e27\u0e19, \u0e41\u0e16\u0e1a\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e15\u0e48\u0e2d \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e33\u0e44\u0e1f\u0e1f\u0e49\u0e32, \u0e41\u0e16\u0e1a\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e31\u0e49\u0e27\u0e15\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c, \u0e41\u0e16\u0e1a\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32, \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07\u0e1a\u0e31\u0e2a\u0e1a\u0e32\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e21\u0e48\u0e2a\u0e32\u0e22 \u0e44\u0e1f\u0e1f\u0e49\u0e32, \u0e25\u0e27\u0e14\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07, \u0e41\u0e17\u0e48\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e1c\u0e2a\u0e21\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125212\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e21\u0e48 234 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125212 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e21\u0e48 234 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1669\/171  \u0e0b\u0e2d\u0e22 \u0e2a\u0e23\u0e13\u0e04\u0e21\u0e19\u0e4c 25 \u0e41\u0e22\u0e01 2-1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125255\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125255 \u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e33 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e48\u0e2d\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u4e0d\u52d5\u7523 89  \u0e16\u0e19\u0e19\u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125590\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21\u0e04\u0e34\u0e27 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125590 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21\u0e04\u0e34\u0e27 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e08\u0e2d\u0e20\u0e32\u0e1e led display, video wall,  digital signage \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 420\/36  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2787 (\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125646\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e1a\u0e4c\u0e04\u0e2d\u0e23\u0e4c\u0e17 \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125646 \u0e1a\u0e08.\u0e44\u0e27\u0e1a\u0e4c\u0e04\u0e2d\u0e23\u0e4c\u0e17 \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e41\u0e1a\u0e14\u0e21\u0e34\u0e19\u0e15\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e32\u0e22\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u82b8\u8853\u30fb\u5a2f\u697d 150  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e22\u0e23\u0e32\u0e21\u0e31\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125671\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35 \u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125671 \u0e1a\u0e08.\u0e41\u0e25\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35 \u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 71201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e04\u0e07\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 546  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e31\u0e0a\u0e14\u0e32 \u0e27\u0e31\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 101, 201, 301, 401 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569020526\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e40\u0e1f\u0e23\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e25\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020526 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e40\u0e1f\u0e23\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e25\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0203569002754\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e1e\u0e35 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002754 \u0e2b\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e1e\u0e35 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-02 5000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e2f \u5efa\u8a2d 88\/394  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034917\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e48\u0e07\u0e44\u0e17\u0e48 \u0e40\u0e2b\u0e34\u0e07 \u0e09\u0e37\u0e2d\u0e40\u0e22\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034917 \u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e48\u0e07\u0e44\u0e17\u0e48 \u0e40\u0e2b\u0e34\u0e07 \u0e09\u0e37\u0e2d\u0e40\u0e22\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034925\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1e\u0e35\u0e04 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034925 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1e\u0e35\u0e04 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d  \u0e42\u0e2d\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 290\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035069\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e17\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e1e\u0e17\u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035069 \u0e1a\u0e08.\u0e41\u0e04\u0e17\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e1e\u0e17\u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e09\u0e35\u0e14\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e15\u0e23\u0e27\u0e08\u0e17\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07 \u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 340\/43-44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008886\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e19\u0e30\u0e1e\u0e25 \u0e40\u0e04\u0e21\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008886 \u0e1a\u0e08.\u0e0a\u0e19\u0e30\u0e1e\u0e25 \u0e40\u0e04\u0e21\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e38\u0e4b\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e44\u0e21\u0e49\u0e14\u0e2d\u0e01 \u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008894\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e01\u0e4a\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47735\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47735\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008894 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e01\u0e4a\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47735 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e01\u0e4a\u0e2a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 160\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0255569001903\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001903 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 109\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0343569001803\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001803 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-02 5000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0405569006318\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e40\u0e08 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006318 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e40\u0e08 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e2d\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e2d\u0e25\u0e2d\u0e35\u0e14\u0e35 (led) \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e16\u0e19\u0e19\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e2d\u0e25\u0e2d\u0e35\u0e14\u0e35 (led) \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e04\u0e21\u0e44\u0e1f  \u0e16\u0e19\u0e19\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e16\u0e19\u0e19\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e2d\u0e25\u0e2d\u0e35\u0e14\u0e35 (led) \u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e16\u0e19\u0e19\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (internet) \u0e44\u0e2d\u0e42\u0e2d\u0e17\u0e35 (iot)\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569014905\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35168 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014905 \u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35168 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e08\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e31\u0e19\u0e14\u0e32\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev conversion) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 255  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0535569000726\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e32 \u0e1f\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000726 \u0e1a\u0e08.\u0e40\u0e1b\u0e32 \u0e1f\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c  \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0745569006978\",\"name_th\":\"\u0e1a\u0e08.3\u0e08\u0e35 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569006978 \u0e1a\u0e08.3\u0e08\u0e35 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e01\u0e38\u0e49\u0e07 \u0e2b\u0e2d\u0e22 \u0e1b\u0e39 \u0e1b\u0e25\u0e32 \u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0755569000520\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35.\u0e08\u0e35. \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c 555 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0755569000520 \u0e1a\u0e08.\u0e14\u0e35.\u0e08\u0e35. \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c 555 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0805569002491\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002491 \u0e1a\u0e08.\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0865569001142\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e42\u0e2a\u0e20\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001142 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e42\u0e2a\u0e20\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 103\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0935569000749\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e35\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000749 \u0e1a\u0e08.\u0e0a\u0e39\u0e01\u0e34\u0e08 \u0e25\u0e35\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e02\u0e32\u0e27 \u0e40\u0e07\u0e34\u0e19 \u0e19\u0e32\u0e01 \u0e44\u0e02\u0e48\u0e21\u0e38\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e17\u0e49\u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 305  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0945569000676\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e23\u0e34\u0e0a\u0e1f\u0e23\u0e38\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000676 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e23\u0e34\u0e0a\u0e1f\u0e23\u0e38\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 5000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 174\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569123902\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123902 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32  \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e41\u0e25\u0e30 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 99\/95  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32&\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e48\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124003\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e4a\u0e01\u0e41\u0e1f\u0e21\u0e35\u0e25\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124003 \u0e1a\u0e08.\u0e1a\u0e34\u0e4a\u0e01\u0e41\u0e1f\u0e21\u0e35\u0e25\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 302\/529  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2771 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124054\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e42\u0e19\u0e27\u0e4c \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124054 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e42\u0e19\u0e27\u0e4c \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30 \u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 96\/80  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124071\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e0d\u0e48\u0e32 \u0e2d\u0e35 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124071 \u0e1a\u0e08.\u0e25\u0e39\u0e0d\u0e48\u0e32 \u0e2d\u0e35 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1131\/221  \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e44\u0e0a\u0e22\u0e28\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124178\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124178 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e40\u0e40\u0e17\u0e19 \u0e40\u0e40\u0e25\u0e30\u0e04\u0e19\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e40\u0e40\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 88\/79  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 35 (\u0e1e\u0e49\u0e2d\u0e21\u0e2d\u0e34\u0e48\u0e21) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124224\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a \u0e17\u0e47\u0e2d\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124224 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a \u0e17\u0e47\u0e2d\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1c\u0e34\u0e27 \u0e07\u0e32\u0e19\u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 238\/7  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124241\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e25\u0e39\u0e0b\u0e35\u0e1f \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124241 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e25\u0e39\u0e0b\u0e35\u0e1f \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u4e0d\u52d5\u7523 1010  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124402\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e41\u0e2e\u0e19\u0e14\u0e34\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124402 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e41\u0e2e\u0e19\u0e14\u0e34\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e2d\u0e14\u0e44\u0e175 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124577\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e15 \u0e23\u0e35\u0e1f\u0e23\u0e34\u0e40\u0e08\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124577 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e15 \u0e23\u0e35\u0e1f\u0e23\u0e34\u0e40\u0e08\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 80200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e15\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 29  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124585\",\"name_th\":\"\u0e1a\u0e08.18 \u0e1a\u0e32\u0e22 \u0e01\u0e49\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124585 \u0e1a\u0e08.18 \u0e1a\u0e32\u0e22 \u0e01\u0e49\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124691\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e34\u0e04\u0e40\u0e40\u0e27\u0e23\u0e4c \u0e40\u0e2d\u0e44\u0e2d (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124691 \u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e34\u0e04\u0e40\u0e40\u0e27\u0e23\u0e4c \u0e40\u0e2d\u0e44\u0e2d (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e40\u0e2d\u0e44\u0e2d (ai) \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 51\/12  \u0e0b\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e07\u0e29\u0e4c\u0e40\u0e27\u0e0a\u0e2d\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124704\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e42\u0e2e\u0e40\u0e15\u0e47\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124704 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e42\u0e2e\u0e40\u0e15\u0e47\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 77 \u0e15\u0e23\u0e2d\u0e01\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e1e\u0e34\u0e21\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021638\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e15\u0e34\u0e2d\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021638 \u0e1a\u0e08.\u0e19\u0e32\u0e15\u0e34\u0e2d\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 47190 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/461  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569020216\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020216 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 186\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020313\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020313 \u0e1a\u0e08.\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e42\u0e2d\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e33 \u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0195569002391\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e38\u0e19\u0e16\u0e27\u0e34\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002391 \u0e1a\u0e08.\u0e25\u0e38\u0e19\u0e16\u0e27\u0e34\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u88fd\u9020 136  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034518\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034518 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e0a\u0e38\u0e14\u0e23\u0e31\u0e1a\u0e41\u0e02\u0e01\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e17\u0e33\u0e04\u0e23\u0e31\u0e27\u0e41\u0e25\u0e30            \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034593\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034593 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 68201 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32: \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u4e0d\u52d5\u7523 388\/246  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034623\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034623 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e33 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e01\u0e23\u0e2d\u0e1a\u0e1e\u0e23\u0e30\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/95-96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034810\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e07\u0e40\u0e2b\u0e2d \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034810 \u0e1a\u0e08.\u0e0a\u0e34\u0e07\u0e40\u0e2b\u0e2d \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034836\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034836 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u533b\u7642\u30fb\u798f\u7949 8\/115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008771\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e21\u0e39\u0e48 \u0e25\u0e39\u0e1a\u0e23\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008771 \u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e21\u0e39\u0e48 \u0e25\u0e39\u0e1a\u0e23\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 46699 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e21\u0e35 (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e21\u0e35\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15) \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e21\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c , \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e25\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e1b\u0e37\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22) \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c,\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25,\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e07, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e2a\u0e49\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e42\u0e25\u0e2b\u0e30, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e0b\u0e48, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c) \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e1a\u0e1a\u0e2a\u0e2d\u0e07\u0e25\u0e49\u0e2d, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008827\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0b\u0e32\u0e27\u0e2d\u0e07\u0e15\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008827 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0b\u0e32\u0e27\u0e2d\u0e07\u0e15\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a api  \u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a ai  \u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e42\u0e15\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2d\u0e31\u0e15 \u0e42\u0e19\u0e21\u0e31\u0e15\u0e34  \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 999\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003540\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e2a\u0e01\u0e38\u0e25\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003540 \u0e1a\u0e08.\u0e01\u0e23\u0e2a\u0e01\u0e38\u0e25\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0415569003360\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003360 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 85\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19\u0e22\u0e32\u0e07 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0575569004217\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e1b\u0e23\u0e34\u0e4a\u0e19\u0e40\u0e0b\u0e2a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004217 \u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e1b\u0e23\u0e34\u0e4a\u0e19\u0e40\u0e0b\u0e2a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004225\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e27\u0e23\u0e34\u0e29\u0e10\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004225 \u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e27\u0e23\u0e34\u0e29\u0e10\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01\u0e2b\u0e49\u0e27\u0e22 \u0e2b\u0e19\u0e2d\u0e07 \u0e04\u0e25\u0e2d\u0e07\u0e1a\u0e36\u0e07 \u0e15\u0e25\u0e34\u0e48\u0e07 \u0e25\u0e33\u0e19\u0e49\u0e33 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e16\u0e19\u0e19 \u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e17\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u5efa\u8a2d 89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004233\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\u0e1f\u0e39\u0e2b\u0e22\u0e27\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004233 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\u0e1f\u0e39\u0e2b\u0e22\u0e27\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e23\u0e48 \u0e41\u0e23\u0e48\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e23\u0e48\u0e15\u0e30\u0e01\u0e31\u0e48\u0e27-\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35 \u9271\u696d\u30fb\u63a1\u77f3 223  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004268\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e40\u0e0a\u0e19\u0e17\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004268 \u0e1a\u0e08.\u0e04\u0e40\u0e0a\u0e19\u0e17\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e40\u0e07\u0e34\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0735569006668\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e2a4545 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006668 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e2a4545 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569006951\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0745569006951 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14 \u4e0d\u52d5\u7523 933  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0765569001372\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001372 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e01\u0e4a\u0e32\u0e0b\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0845569009950\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2d\u0e2d\u0e1f \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":5000000,\"capital_display\":\"5,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569009950 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2d\u0e2d\u0e1f \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 5000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569035395\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e01\u0e40\u0e0b\u0e2d\u0e40\u0e25\u0e2d\u0e40\u0e23\u0e15 \u0e19\u0e2d\u0e25\u0e40\u0e25\u0e08 \u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":4990000,\"capital_display\":\"4,990,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035395 \u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e01\u0e40\u0e0b\u0e2d\u0e40\u0e25\u0e2d\u0e40\u0e23\u0e15 \u0e19\u0e2d\u0e25\u0e40\u0e25\u0e08 \u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 4990000 47912 \u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e2d\u0e14\u0e34\u0e42\u0e2d\u0e1a\u0e38\u0e4a\u0e04\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e14\u0e34\u0e42\u0e2d\u0e1a\u0e38\u0e4a\u0e04\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569129111\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e04\u0e1a\u0e35\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4900000,\"capital_display\":\"4,900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46434\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46434\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129111 \u0e1a\u0e08.\u0e1e\u0e35\u0e04\u0e1a\u0e35\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4900000 46434 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e01\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/526  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 68 \u0e41\u0e22\u0e01 2-12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026508\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e07\u0e08\u0e38\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4800000,\"capital_display\":\"4,800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026508 \u0e1a\u0e08.\u0e08\u0e07\u0e08\u0e38\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4800000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 26\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0915569000323\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e17\u0e23\u0e32\u0e22\u0e18\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4800000,\"capital_display\":\"4,800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0915569000323 \u0e1a\u0e08.\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27\u0e17\u0e23\u0e32\u0e22\u0e18\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4800000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21  \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 1538  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569034747\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e31\u0e25\u0e40\u0e21\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":4800000,\"capital_display\":\"4,800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034747 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e31\u0e25\u0e40\u0e21\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 4800000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e17\u0e34 \u0e41\u0e1b\u0e23\u0e07\u0e2a\u0e35\u0e1f\u0e31\u0e19 \u0e41\u0e1b\u0e23\u0e07\u0e2a\u0e35\u0e1f\u0e49\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2b\u0e31\u0e27\u0e41\u0e1b\u0e23\u0e07\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e44\u0e2b\u0e21\u0e02\u0e31\u0e14\u0e1f\u0e31\u0e19\u0e0a\u0e19\u0e34\u0e14\u0e40\u0e2a\u0e49\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e01\u0e49\u0e32\u0e19 \u0e41\u0e1b\u0e23\u0e07\u0e0b\u0e2d\u0e01\u0e1f\u0e31\u0e19 \u0e41\u0e1b\u0e23\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1f\u0e31\u0e19 \u0e44\u0e21\u0e49\u0e08\u0e34\u0e49\u0e21\u0e1f\u0e31\u0e19  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0905569006411\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006411 \u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4500000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0405569007098\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e42\u0e15\u0e23\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007098 \u0e1a\u0e08.\u0e40\u0e1b\u0e42\u0e15\u0e23\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4500000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 281  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007144\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e08.\u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 1996 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007144 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e08.\u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 1996 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4500000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569134190\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e17\u0e23\u0e32 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134190 \u0e1a\u0e08.\u0e0b\u0e39\u0e17\u0e23\u0e32 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 4500000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e2d\u0e20\u0e32\u0e1e\u0e0a\u0e19\u0e34\u0e14\u0e1c\u0e25\u0e36\u0e01\u0e40\u0e2b\u0e25\u0e27 (lcd) \u0e08\u0e2d\u0e20\u0e32\u0e1e\u0e0a\u0e19\u0e34\u0e14 led \u0e08\u0e2d\u0e21\u0e2d\u0e19\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e2d\u0e17\u0e31\u0e0a\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e2d\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 1521  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133266\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e21\u0e2d\u0e23\u0e34\u0e15\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133266 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e21\u0e2d\u0e23\u0e34\u0e15\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4500000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e07 \u0e17\u0e33\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u91d1\u878d\u30fb\u4fdd\u967a 942\/43  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e32\u0e0d\u0e2d\u0e34\u0e2a\u0e2a\u0e23\u0e30\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132511\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34\u0e0b\u0e31\u0e19 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52109\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52109\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132511 \u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34\u0e0b\u0e31\u0e19 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 4500000 52109 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47\u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e49\u0e27) \u904b\u8f38\u30fb\u7269\u6d41 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e3523 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1723 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0445569001707\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001707 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 4500000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e16\u0e44\u0e16 \u0e23\u0e16\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e15\u0e31\u0e14\u0e2d\u0e49\u0e2d\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e35\u0e43\u0e1a\u0e2d\u0e49\u0e2d\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/2  \u0e0b\u0e2d\u0e22 \u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c 70 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0125569025447\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e2a\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e04\u0e32\u0e17\u0e22\u0e39\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85429\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85429\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025447 \u0e1a\u0e08.\u0e23\u0e31\u0e2a\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e04\u0e32\u0e17\u0e22\u0e39\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 4500000 85429 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e23\u0e31\u0e2a\u0e40\u0e0b\u0e35\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u6559\u80b2 65\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0405569006482\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006482 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 4500000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 281  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0605569001926\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e21\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001926 \u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e21\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 4500000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u904b\u8f38\u30fb\u7269\u6d41 118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0845569010052\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e0b\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010052 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e0b\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 4\/179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569008819\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e48\u0e32\u0e44\u0e17\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":4500000,\"capital_display\":\"4,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008819 \u0e1a\u0e08.\u0e22\u0e48\u0e32\u0e44\u0e17\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 4500000 72109 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/318  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015219\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4400000,\"capital_display\":\"4,400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015219 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4400000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0405569006750\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e1f\u0e48\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4219000,\"capital_display\":\"4,219,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006750 \u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e1f\u0e48\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4219000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e20\u0e31\u0e15\u0e23\u0e32\u0e04\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e1a\u0e32\u0e23\u0e4c \u0e14\u0e34\u0e2a\u0e42\u0e01\u0e49\u0e40\u0e17\u0e04 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e42\u0e14\u0e22\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 369  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569143113\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e25\u0e35 \u0e40\u0e14\u0e27\u0e35\u0e48 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143113 \u0e1a\u0e08.\u0e40\u0e14\u0e25\u0e35 \u0e40\u0e14\u0e27\u0e35\u0e48 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 44\/2  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e32\u0e42\u0e21\u0e17\u0e22\u0e4c 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143334\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e19\u0e07 \u0e1e\u0e35\u0e27\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143334 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e19\u0e07 \u0e1e\u0e35\u0e27\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e1a\u0e1a epc turnkey \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e42\u0e23\u0e07\u0e23\u0e16  \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e1a\u0e1a  \u0e15\u0e23\u0e27\u0e08\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u5efa\u8a2d 32\/1  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 56 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143369\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e48\u0e22\u0e44\u0e17 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143369 \u0e1a\u0e08.\u0e40\u0e21\u0e48\u0e22\u0e44\u0e17 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/590  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143407\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e23\u0e4c\u0e23\u0e32\u0e19\u0e35 \u0e44\u0e1f\u0e19\u0e4c \u0e21\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143407 \u0e1a\u0e08.\u0e14\u0e39\u0e23\u0e4c\u0e23\u0e32\u0e19\u0e35 \u0e44\u0e1f\u0e19\u0e4c \u0e21\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 205   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 101 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 64 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569039561\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e01\u0e15\u0e2d\u0e40\u0e23\u0e35\u0e22 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039561 \u0e1a\u0e08.\u0e27\u0e34\u0e01\u0e15\u0e2d\u0e40\u0e23\u0e35\u0e22 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 195\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039641\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e23\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039641 \u0e1a\u0e08.\u0e0a\u0e23\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 8\/105   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 401 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0835569013914\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013914 \u0e1a\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 70201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 (m&a)  \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/8   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a01 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0905569006429\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e15\u0e49\u0e32 \u0e42\u0e2e\u0e21 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006429 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e15\u0e49\u0e32 \u0e42\u0e2e\u0e21 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 4000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36  \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569142729\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e21\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142729 \u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e21\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 205   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 102 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 64 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025153\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025153 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 4000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 96\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e1a\u0e38\u0e0d\u0e28\u0e34\u0e23\u0e34 15 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 27 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569010058\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e19\u0e40\u0e09\u0e34\u0e19 \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010058 \u0e1a\u0e08.\u0e2e\u0e32\u0e19\u0e40\u0e09\u0e34\u0e19 \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 150\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001715\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e41\u0e2d\u0e25 \u0e25\u0e35\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001715 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e41\u0e2d\u0e25 \u0e25\u0e35\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 4000000 64929 \u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d \u91d1\u878d\u30fb\u4fdd\u967a 173  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569039447\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08  \u0e41\u0e2d\u0e19\u0e14\u0e4c  \u0e17\u0e35  \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039447 \u0e1a\u0e08.\u0e40\u0e08  \u0e41\u0e2d\u0e19\u0e14\u0e4c  \u0e17\u0e35  \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 245\/113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0505569016851\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e22\u0e23\u0e32 \u0e0b\u0e2d\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016851 \u0e1a\u0e08.\u0e44\u0e2d\u0e22\u0e23\u0e32 \u0e0b\u0e2d\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 4000000 62022 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 50\/11   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a1 \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001811\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e08\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001811 \u0e1a\u0e08.\u0e20\u0e32\u0e08\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 4000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e42\u0e23\u0e04 \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e1e\u0e17\u0e22\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 282\/1  \u0e16\u0e19\u0e19\u0e09\u0e31\u0e15\u0e23\u0e44\u0e0a\u0e22 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569141455\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25 \u0e0b\u0e31\u0e19\u0e0a\u0e32\u0e22\u0e19\u0e4c \u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"88901\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"88901\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141455 \u0e1a\u0e08.\u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25 \u0e0b\u0e31\u0e19\u0e0a\u0e32\u0e22\u0e19\u0e4c \u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 88901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e14\u0e47\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01  \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 130\/5  \u0e0b\u0e2d\u0e22 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141650\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e42\u0e1b\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141650 \u0e1a\u0e08.\u0e25\u0e39\u0e42\u0e1b\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 73101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2823\/3  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142141\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e21\u0e32\u0e23\u0e34\u0e44\u0e17\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142141 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e21\u0e32\u0e23\u0e34\u0e44\u0e17\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 95\/91  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e27\u0e34\u0e19\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569039145\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e48\u0e19\u0e44\u0e17\u0e48 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039145 \u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e48\u0e19\u0e44\u0e17\u0e48 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039315\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e25\u0e25\u0e35\u0e48 \u0e23\u0e32\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039315 \u0e1a\u0e08.\u0e40\u0e0a\u0e25\u0e25\u0e35\u0e48 \u0e23\u0e32\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 8\/105   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 301 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039382\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e40\u0e04\u0e23\u0e2a\u0e15\u0e4c \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039382 \u0e1a\u0e08.\u0e44\u0e17\u0e40\u0e04\u0e23\u0e2a\u0e15\u0e4c \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 168\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0405569007276\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e2e\u0e21\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007276 \u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e2e\u0e21\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 545  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 \u0e1a\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e27 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e2d\u0e01 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016771\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e1f\u0e32 \u0e40\u0e2e\u0e25\u0e18\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016771 \u0e1a\u0e08.\u0e23\u0e32\u0e1f\u0e32 \u0e40\u0e2e\u0e25\u0e18\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e1a\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30 \u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19 \u533b\u7642\u30fb\u798f\u7949 1  \u0e0b\u0e2d\u0e22 1 (\u0e16\u0e19\u0e19\u0e42\u0e0a\u0e15\u0e19\u0e32) \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e15\u0e19\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0655569002434\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e19\u0e32\u0e42\u0e19 \u0e41\u0e25\u0e1a\u0e2a\u0e4c(\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10619\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10619\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002434 \u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e19\u0e32\u0e42\u0e19 \u0e41\u0e25\u0e1a\u0e2a\u0e4c(\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 10619 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 487\/3-4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0805569002921\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e01\u0e25\u0e01\u0e32\u0e23\u0e42\u0e25\u0e2b\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002921 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e01\u0e25\u0e01\u0e32\u0e23\u0e42\u0e25\u0e2b\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e1e\u0e31\u0e1a\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e01\u0e25\u0e36\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 194  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013833\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e14\u0e23\u0e31\u0e21 \u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e34\u0e0a \u0e1a\u0e32\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96305\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96305\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013833 \u0e1a\u0e08.\u0e1a\u0e2d\u0e14\u0e23\u0e31\u0e21 \u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e34\u0e0a \u0e1a\u0e32\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 4000000 96305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e1b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e41\u0e1a\u0e1a\u0e15\u0e38\u0e23\u0e01\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e2e\u0e31\u0e21\u0e21\u0e31\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e1a\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e2b\u0e49\u0e2d\u0e07\u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32 \u0e2d\u0e48\u0e32\u0e07\u0e19\u0e49\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e08\u0e32\u0e01\u0e38\u0e0b\u0e0b\u0e35 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e14\u0e1c\u0e34\u0e27 \u0e01\u0e32\u0e23\u0e1e\u0e2d\u0e01\u0e1c\u0e34\u0e27 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 21\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0205569039111\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039111 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 78\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028098\",\"name_th\":\"\u0e1a\u0e08.2\u0e1a\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e01 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028098 \u0e1a\u0e08.2\u0e1a\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e01 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 4000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 72\/152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569139949\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e2d\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139949 \u0e1a\u0e08.\u0e40\u0e23\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e2d\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/24  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140297\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140297 \u0e1a\u0e08.\u0e1a\u0e35 \u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 68201 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 209  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 64 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140475\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e21\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140475 \u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e21\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58,60,62,64  \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140556\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e1a\u0e35\u0e40\u0e04 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140556 \u0e1a\u0e08.\u0e44\u0e2d\u0e1a\u0e35\u0e40\u0e04 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 919\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48\u0e40\u0e17\u0e23\u0e14\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e1a\u0e39\u0e18 jb307 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140734\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140734 \u0e1a\u0e08.\u0e14\u0e35\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1179  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e34\u0e19\u0e25\u0e2d\u0e07 \u0e1a\u0e34\u0e27\u0e14\u0e34\u0e49\u0e07  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140793\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e27\u0e19\u0e0b\u0e32\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35-\u0e40\u0e2d\u0e47\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140793 \u0e1a\u0e08.\u0e2b\u0e27\u0e19\u0e0b\u0e32\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35-\u0e40\u0e2d\u0e47\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c 111 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140840\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e27\u0e31\u0e19 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140840 \u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e27\u0e31\u0e19 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e21\u0e31\u0e04\u0e04\u0e38\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 111\/58  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569003262\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e0a\u0e31\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 999\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003262 \u0e2b\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e0a\u0e31\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 999 2569-07-24 4000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c (\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 ) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 333\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038866\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e215 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038866 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e215 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009912\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e17\u0e07 \u0e08\u0e27\u0e35\u0e49\u0e25\u0e35\u0e48 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009912 \u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e17\u0e07 \u0e08\u0e27\u0e35\u0e49\u0e25\u0e35\u0e48 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 952\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013655\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e1f\u0e32\u0e2a\u0e15\u0e4c\u0e41\u0e17\u0e23\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74909\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74909\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013655 \u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e1f\u0e32\u0e2a\u0e15\u0e4c\u0e41\u0e17\u0e23\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 74909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33 \u0e22\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 (visa) \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27  \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 (work permit) \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/8   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a02 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013736\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013736 \u0e1a\u0e08.\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 4000000 47113 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569139078\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e1e\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139078 \u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e1e\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e20\u0e32\u0e1e \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u82b8\u8853\u30fb\u5a2f\u697d 665  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e0a\u0e14\u0e32\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139086\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e04\u0e40\u0e1a\u0e1f (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139086 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e04\u0e40\u0e1a\u0e1f (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27 \u0e01\u0e32\u0e41\u0e1f\u0e1a\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 319  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e15\u0e38\u0e23\u0e31\u0e2a\u0e08\u0e32\u0e21\u0e08\u0e38\u0e23\u0e35  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e17\u0e35\u0e17\u0e3511 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 24 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569038653\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e49\u0e2b\u0e25\u0e07\u0e40\u0e0b\u0e35\u0e22\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038653 \u0e1a\u0e08.\u0e2d\u0e35\u0e49\u0e2b\u0e25\u0e07\u0e40\u0e0b\u0e35\u0e22\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 889\/375,889\/376  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0345569003379\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003379 \u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003912\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e38\u0e14\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52219\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52219\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003912 \u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e38\u0e14\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 52219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u904b\u8f38\u30fb\u7269\u6d41 213\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e01\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016592\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e42\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016592 \u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e42\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 97\/5  \u0e16\u0e19\u0e19\u0e23\u0e30\u0e41\u0e01\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0745569007851\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e04\u0e17\u0e0a\u0e4c \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007851 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e04\u0e17\u0e0a\u0e4c \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 57\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007877\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e2d\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007877 \u0e1a\u0e08.\u0e2d\u0e35\u0e2d\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u0e0a\u0e32\u0e1a\u0e39 \u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e19\u0e17\u0e35 \u5bbf\u6cca\u30fb\u98f2\u98df 103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0815569002211\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e0b\u0e31\u0e19\u0e40\u0e0b\u0e47\u0e15 \u0e04\u0e23\u0e39\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002211 \u0e1a\u0e08.\u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e0b\u0e31\u0e19\u0e40\u0e0b\u0e47\u0e15 \u0e04\u0e23\u0e39\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 32\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569013639\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e0b\u0e2d\u0e1f\u0e17\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013639 \u0e1a\u0e08.\u0e04\u0e27\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e0b\u0e2d\u0e1f\u0e17\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 65\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013647\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e41\u0e25\u0e07\u0e40\u0e01\u0e27\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74901\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74901\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013647 \u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e41\u0e25\u0e07\u0e40\u0e01\u0e27\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 4000000 74901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e48\u0e32\u0e21 \u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u0e41\u0e1b\u0e25\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e1b\u0e25\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e25\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 65\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569138039\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e1f\u0e34\u0e23\u0e32 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138039 \u0e1a\u0e08.\u0e42\u0e2d\u0e1f\u0e34\u0e23\u0e32 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 4000000 32112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 41\/4  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e01\u0e25\u0e14\u0e4c\u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3f43 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3f \u0e0b\u0e2d\u0e22 \u0e15\u0e23\u0e2d\u0e01\u0e40\u0e27\u0e17 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138381\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e42\u0e23\u0e22\u0e32 \u0e40\u0e08\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138381 \u0e1a\u0e08.\u0e42\u0e2d\u0e42\u0e23\u0e22\u0e32 \u0e40\u0e08\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 919\/305  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48\u0e40\u0e17\u0e23\u0e14\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 305 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 24 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138438\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138438 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1\/53  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 101 \u0e0b\u0e2d\u0e22 51 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0815569002190\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e07 \u0e41\u0e1e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002190 \u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e07 \u0e41\u0e1e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e04\u0e32\u0e40\u0e1f\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 79\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569013558\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e23\u0e34\u0e22\u0e32\u0e19\u0e34 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013558 \u0e1a\u0e08.\u0e1a\u0e34\u0e23\u0e34\u0e22\u0e32\u0e19\u0e34 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 90\/6  \u0e16\u0e19\u0e19\u0e42\u0e04\u0e01\u0e42\u0e15\u0e19\u0e14 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569136893\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e42\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e2a\u0e44\u0e1b\u0e0b\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136893 \u0e1a\u0e08.\u0e40\u0e1f\u0e42\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e2a\u0e44\u0e1b\u0e0b\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 4000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 57 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137598\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e25\u0e35 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137598 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e25\u0e35 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 4000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 555\/28  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024106\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e19\u0e25\u0e35\u0e48 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024106 \u0e1a\u0e08.\u0e40\u0e1e\u0e19\u0e25\u0e35\u0e48 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 4000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e23\u0e48\u0e17\u0e35\u0e48\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/12   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 103 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027482\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e44\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027482 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e44\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 4000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e42\u0e14\u0e22\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 305\/112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022499\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e35\u0e48 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022499 \u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e35\u0e48 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 9\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569038114\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 111 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038114 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 111 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 453\/210  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0505569016436\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e31\u0e19\u0e1c\u0e31\u0e01\u0e2b\u0e27\u0e32\u0e19 \u0e14\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016436 \u0e1a\u0e08.\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e31\u0e19\u0e1c\u0e31\u0e01\u0e2b\u0e27\u0e32\u0e19 \u0e14\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 4000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e1c\u0e07 \u0e25\u0e47\u0e2d\u0e04 \u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u4e0d\u52d5\u7523 246\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0103569007803\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e01\u0e15 \u0e14\u0e47\u0e2d\u0e01 \u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007803 \u0e2b\u0e08.\u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e01\u0e15 \u0e14\u0e47\u0e2d\u0e01 \u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-20 4000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e38\u0e19\u0e31\u0e02 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 79  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.\u0e59 \u0e0b\u0e2d\u0e22 53 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136524\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e23\u0e32 \u0e40\u0e08\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136524 \u0e1a\u0e08.\u0e2d\u0e35\u0e23\u0e32 \u0e40\u0e08\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1e\u0e25\u0e2d\u0e22 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u88fd\u9020 1055\/885  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e32\u0e23\u0e4c \u0e0b\u0e35 \u0e40\u0e04 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 37 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136532\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e19\u0e17\u0e4c\u0e04\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136532 \u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e19\u0e17\u0e4c\u0e04\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e17\u0e33\u0e14\u0e49\u0e27\u0e22\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e07\u0e34\u0e19 \u0e41\u0e1e\u0e25\u0e17\u0e34\u0e19\u0e31\u0e21 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e02\u0e32\u0e27 \u0e41\u0e25\u0e30 \u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/1  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 65 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136541\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e19\u0e2a\u0e34\u0e19\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136541 \u0e1a\u0e08.\u0e01\u0e32\u0e19\u0e2a\u0e34\u0e19\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 295\/95  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569022260\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022260 \u0e1a\u0e08.\u0e1e\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 32\/145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569038009\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1e\u0e23\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038009 \u0e1a\u0e08.\u0e42\u0e1e\u0e23\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 55\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009645\",\"name_th\":\"\u0e1a\u0e08. \u0e0b\u0e34\u0e19\u0e1f\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009645 \u0e1a\u0e08. \u0e0b\u0e34\u0e19\u0e1f\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 41002 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32  \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 555\/21  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002314\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e42\u0e04 \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35 \u0e40\u0e08\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32113\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32113\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002314 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e42\u0e04 \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35 \u0e40\u0e08\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 32113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 212\/4  \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e2b\u0e25\u0e27\u0e07 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0815569002181\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e34 \u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002181 \u0e1a\u0e08.\u0e2a\u0e15\u0e34 \u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 273  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0845569010605\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e1f\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010605 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e1f\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 4000000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e08\u0e32\u0e01\u0e44\u0e01\u0e48 \u0e40\u0e0a\u0e48\u0e19 \u0e44\u0e01\u0e48\u0e2b\u0e21\u0e31\u0e01 \u0e44\u0e01\u0e48\u0e22\u0e48\u0e32\u0e07 \u0e44\u0e01\u0e48\u0e17\u0e2d\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 185\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569009564\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e4b\u0e32\u0e40\u0e1f\u0e22\u0e25\u0e35\u0e48 \u0e19\u0e34\u0e27 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23959\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23959\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009564 \u0e1a\u0e08.\u0e15\u0e4b\u0e32\u0e40\u0e1f\u0e22\u0e25\u0e35\u0e48 \u0e19\u0e34\u0e27 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 4000000 23959 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1b\u0e39\u0e19\u0e21\u0e2d\u0e23\u0e4c\u0e15\u0e32\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 1189\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013302\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e17\u0e39\u0e25\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013302 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e17\u0e39\u0e25\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 22\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569135072\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e01\u0e0b\u0e34\u0e2d\u0e2d\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135072 \u0e1a\u0e08.\u0e41\u0e2d\u0e01\u0e0b\u0e34\u0e2d\u0e2d\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 46414 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 - \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/164  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e40\u0e27\u0e2c\u0e38\u0e27\u0e19\u0e32\u0e23\u0e32\u0e21 13\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135285\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e1e\u0e17\u0e23\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135285 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e1e\u0e17\u0e23\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e40\u0e01\u0e25\u0e37\u0e2d\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e  \u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/49  \u0e16\u0e19\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135340\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e34\u0e07\u0e15\u0e34\u0e07 \u0e04\u0e32\u0e23\u0e4c \u0e1a\u0e31\u0e15\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135340 \u0e1a\u0e08.\u0e15\u0e34\u0e07\u0e15\u0e34\u0e07 \u0e04\u0e32\u0e23\u0e4c \u0e1a\u0e31\u0e15\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1213\/84  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 94 (\u0e1b\u0e31\u0e0d\u0e08\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023631\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e0a \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45303\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45303\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023631 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e0a \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 45303 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07-\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 109\/609,610  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023754\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023754 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 47912 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b\u0e02\u0e49\u0e32\u0e21\u0e1e\u0e23\u0e21\u0e41\u0e14\u0e19  (cross-border e-commerce) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2122\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023771\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023771 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 - \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 508\/12  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569037550\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e14\u0e07\u0e04\u0e4c \u0e2d\u0e2d\u0e1f  \u0e2d\u0e34\u0e07\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e1e\u0e35\u0e17\u0e35\u0e27\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037550 \u0e1a\u0e08.\u0e41\u0e14\u0e07\u0e04\u0e4c \u0e2d\u0e2d\u0e1f  \u0e2d\u0e34\u0e07\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e1e\u0e35\u0e17\u0e35\u0e27\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 63\/93  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037592\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2d\u0e14\u0e34\u0e22\u0e32 \u0e19\u0e34\u0e27 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037592 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2d\u0e14\u0e34\u0e22\u0e32 \u0e19\u0e34\u0e27 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e35\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e2d\u0e35\u0e1e\u0e47\u0e2d\u0e01\u0e0b\u0e35\u0e48 \u0e2a\u0e35\u0e17\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e14\u0e01\u0e23\u0e48\u0e2d\u0e19 \u0e2a\u0e35\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e2a\u0e19\u0e34\u0e21 \u0e2a\u0e35\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e2a\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\/\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037606\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e2e\u0e07  \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17  \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037606 \u0e1a\u0e08.\u0e22\u0e39\u0e2e\u0e07  \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17  \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 43210 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e44\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e01\u0e47\u0e1a\u0e01\u0e31\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07   \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 24\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037673\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037673 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e2d\u0e30\u0e42\u0e01\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e32 \u0e22\u0e32\u0e2a\u0e39\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 113\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 15 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009505\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c  \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 )  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009505 \u0e1a\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c  \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 )  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 41002 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 555\/21  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0345569003271\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e23\u0e0b\u0e4c \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003271 \u0e1a\u0e08.\u0e44\u0e23\u0e0b\u0e4c \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0835569013272\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e27\u0e34\u0e04\u0e15\u0e31\u0e2a \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013272 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e27\u0e34\u0e04\u0e15\u0e31\u0e2a \u0e27\u0e35\u0e15\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 4000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 58\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569134335\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e44\u0e2d\u0e0b\u0e35 \u0e17\u0e31\u0e27\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134335 \u0e1a\u0e08.\u0e17\u0e35\u0e44\u0e2d\u0e0b\u0e35 \u0e17\u0e31\u0e27\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 87\/54-55  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e21\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0225569002268\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e40\u0e04 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002268 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e40\u0e04 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 4000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 109\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569133789\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e19\u0e17\u0e4c \u0e2d\u0e32\u0e22\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47731\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47731\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133789 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e19\u0e17\u0e4c \u0e2d\u0e32\u0e22\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 4000000 47731 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07 \u0e41\u0e27\u0e48\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e27\u0e48\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/287  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133851\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e08\u0e34\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133851 \u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e08\u0e34\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 4000000 46521 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 719  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 23  \u0e42\u0e0b\u0e19c \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e219 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0215569009475\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009475 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 38\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0825569001142\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e2a\u0e04\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001142 \u0e1a\u0e08.\u0e2d\u0e34\u0e2a\u0e04\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569013167\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e2d\u0e0a\u0e01\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013167 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e2d\u0e0a\u0e01\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 4000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 96\/211  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010435\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e31\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010435 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e31\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 4000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 319\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010443\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e31\u0e0d\u0e0d\u0e32 \u0e23\u0e35\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f \u0e40\u0e14\u0e1f. \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010443 \u0e1a\u0e08.\u0e2d\u0e23\u0e31\u0e0d\u0e0d\u0e32 \u0e23\u0e35\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f \u0e40\u0e14\u0e1f. \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 4000000 55101 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 41\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0953569000178\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e34\u0e27\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0953569000178 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e34\u0e27\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 2569-07-15 4000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e41\u0e02\u0e01 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e31\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14 \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e14\u0e49\u0e32\u0e19\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e42\u0e14\u0e22\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 122\/74  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22 15 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569132863\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132863 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e01\u0e48 \u0e41\u0e1e\u0e19\u0e40\u0e04\u0e49\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e01\u0e19\u0e49\u0e33\u0e22\u0e48\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e35 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b38 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 b \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133185\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e44\u0e2d\u0e1e\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133185 \u0e1a\u0e08.\u0e1e\u0e35\u0e44\u0e2d\u0e1e\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 70100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49 \u0e41\u0e01\u0e48\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e02\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01. \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02. \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e04. \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e07. \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e19\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08. \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 502  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e01\u0e29\u0e23 \u0e2d\u0e31\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 8a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023291\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e31\u0e07\u0e0b\u0e34\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e42\u0e25\u0e2b\u0e30 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023291 \u0e1a\u0e08.\u0e2a\u0e27\u0e31\u0e07\u0e0b\u0e34\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e42\u0e25\u0e2b\u0e30 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 25119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1c\u0e48\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e1c\u0e48\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e42\u0e25\u0e2b\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u88fd\u9020 88\/114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002233\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e40\u0e23\u0e0a\u0e35 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002233 \u0e1a\u0e08.\u0e04\u0e39\u0e40\u0e23\u0e0a\u0e35 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e25\u0e2d\u0e22\u0e14\u0e34\u0e1a \u0e1e\u0e25\u0e2d\u0e22\u0e01\u0e49\u0e2d\u0e19 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e2b\u0e34\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e2d\u0e22\u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003795\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a.\u0e27\u0e32\u0e22. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003795 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a.\u0e27\u0e32\u0e22. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 153  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003825\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35 \u0e27\u0e31\u0e19 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003825 \u0e1a\u0e08.\u0e14\u0e35 \u0e27\u0e31\u0e19 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e34\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0345569003204\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003204 \u0e1a\u0e08.\u0e21\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e1b\u0e42\u0e25 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1a\u0e19\u0e14\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47\u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 235  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0475569001537\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e32\u0e07\u0e42\u0e08\u0e27 \u0e15\u0e07\u0e0b\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001537 \u0e1a\u0e08.\u0e2b\u0e32\u0e07\u0e42\u0e08\u0e27 \u0e15\u0e07\u0e0b\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569012993\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e25\u0e15\u0e48\u0e32\u0e19 \u0e2d\u0e31\u0e25\u0e0a\u0e32\u0e21 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012993 \u0e1a\u0e08.\u0e2a\u0e38\u0e25\u0e15\u0e48\u0e32\u0e19 \u0e2d\u0e31\u0e25\u0e0a\u0e32\u0e21 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e15\u0e31\u0e4b\u0e27\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e15\u0e31\u0e4b\u0e27\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e15\u0e31\u0e48\u0e27\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 204\/26  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 200 \u0e1b\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010346\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35 \u0e41\u0e2d\u0e19 \u0e14\u0e35 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010346 \u0e1a\u0e08.\u0e14\u0e35 \u0e41\u0e2d\u0e19 \u0e14\u0e35 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5efa\u8a2d 59\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010389\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e07\u0e04\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010389 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e07\u0e04\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e40\u0e01\u0e2a\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22 \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 34\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569132219\",\"name_th\":\"\u0e1a\u0e08.69 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132219 \u0e1a\u0e08.69 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 4000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e01\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 69 \u0e41\u0e22\u0e01 8-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023185\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023185 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e2d\u0e35\u0e1e\u0e47\u0e2d\u0e01\u0e0b\u0e35\u0e48 (epoxy flooring)  \u0e07\u0e32\u0e19\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e19\u0e31\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e14\u0e01\u0e23\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e16\u0e34\u0e15 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e19\u0e0b\u0e36\u0e21  \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e2d\u0e22\u0e23\u0e31\u0e48\u0e27 \u0e07\u0e32\u0e19\u0e09\u0e19\u0e27\u0e19\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e14\u0e01\u0e23\u0e48\u0e2d\u0e19\u0e1c\u0e19\u0e31\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48  \u0e07\u0e32\u0e19\u0e15\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1b\u0e49\u0e32\u0e22\u0e08\u0e23\u0e32\u0e08\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e49\u0e32\u0e22\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 (smart system) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\/\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 (low voltage system) \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e1b\u0e32  \u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 (hvac) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e04\u0e23\u0e1a\u0e0a\u0e38\u0e14 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e02\u0e08\u0e31\u0e14\u0e2a\u0e19\u0e34\u0e21 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e14\u0e01\u0e23\u0e48\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e16\u0e21\u0e14\u0e34\u0e19  \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e21\u0e25\u0e1e\u0e34\u0e29 \u0e43\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e1c\u0e19\u0e31\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 (curtain wall) \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39?\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e09\u0e19\u0e27\u0e19\u0e1c\u0e19\u0e31\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01  \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e23\u0e27\u0e21\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 (turnkey) \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5efa\u8a2d 444\/39  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0145569004598\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e34\u0e07 \u0e2d\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004598 \u0e1a\u0e08.\u0e1b\u0e34\u0e07 \u0e2d\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 4000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2b\u0e23\u0e37\u0e2d \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07 \u5efa\u8a2d 63\/305  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569037045\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037045 \u0e1a\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 4000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e01\u0e14 \u0e01\u0e32\u0e23\u0e04\u0e25\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e35\u0e1a          \u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e14\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e14\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e04\u0e1a \u0e01\u0e32\u0e23\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 (\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04) \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e15\u0e32\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23          \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 47\/78,47\/79,47\/80  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0425569000514\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e0b\u0e35\u0e41\u0e1e\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000514 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e0b\u0e35\u0e41\u0e1e\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 151  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0745569007362\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e22\u0e34\u0e07\u0e14\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27502\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27502\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007362 \u0e1a\u0e08.\u0e2b\u0e22\u0e34\u0e07\u0e14\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 4000000 27502 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e15\u0e32\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u88fd\u9020 288\/50,288\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0255569001989\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0b. \u0e27\u0e32\u0e22. \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001989 \u0e1a\u0e08.\u0e40\u0e2d\u0e0b. \u0e27\u0e32\u0e22. \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 4000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07            \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 234\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569131140\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e17\u0e39  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131140 \u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e17\u0e39  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e0d\u52d5\u7523 87\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131158\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e17\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131158 \u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e17\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e0d\u52d5\u7523 87\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023053\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35.\u0e08\u0e37\u0e2d\u0e1c\u0e39 \u0e17\u0e39\u0e25\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e14\u0e19\u0e35\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023053 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35.\u0e08\u0e37\u0e2d\u0e1c\u0e39 \u0e17\u0e39\u0e25\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e14\u0e19\u0e35\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e07  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e42\u0e25\u0e2b\u0e38 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e25\u0e34\u0e40\u0e17\u0e35\u0e22\u0e21  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026052\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e17\u0e27\u0e35\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026052 \u0e1a\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e17\u0e27\u0e35\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/556  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026079\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026079 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/22   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036669\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e15\u0e4b\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036669 \u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e15\u0e4b\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48  \u0e41\u0e25\u0e30  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 255\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036685\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e27\u0e19 \u0e2b\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"26109\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"26109\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036685 \u0e1a\u0e08.\u0e09\u0e27\u0e19 \u0e2b\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 26109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e40\u0e22\u0e47\u0e19 \u88fd\u9020 88\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036766\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e1b \u0e04\u0e2d\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036766 \u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e1b \u0e04\u0e2d\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e2d\u0e30\u0e42\u0e01\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e32 \u0e22\u0e32\u0e2a\u0e39\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 17\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036774\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e35\u0e22\u0e23\u0e4c\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036774 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e35\u0e22\u0e23\u0e4c\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e01\u0e25\u0e32\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 565\/95 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007200\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e23\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007200 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e23\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e04\u0e25\u0e31\u0e1a \u0e42\u0e23\u0e07\u0e22\u0e34\u0e21\u0e40\u0e19\u0e40\u0e0b\u0e35\u0e22\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 1277  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0365569001422\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e04\u0e23\u0e32\u0e1f \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001422 \u0e1a\u0e08.\u0e41\u0e17\u0e07\u0e04\u0e4c\u0e04\u0e23\u0e32\u0e1f \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07\u0e41\u0e17\u0e47\u0e07\u0e01\u0e4c\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e16\u0e31\u0e07\u0e19\u0e49\u0e33\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001685\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e22\u0e15\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001685 \u0e1a\u0e08.\u0e42\u0e22\u0e15\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 191  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0835569012829\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1a\u0e4a\u0e17 \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012829 \u0e1a\u0e08.\u0e42\u0e1a\u0e4a\u0e17 \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 4000000 10794 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u88fd\u9020 39  \u0e16\u0e19\u0e19\u0e15\u0e25\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569130241\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e07\u0e40\u0e08\u0e4b\u0e2d \u0e1e\u0e34\u0e27\u0e23\u0e34\u0e1f\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130241 \u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e07\u0e40\u0e08\u0e4b\u0e2d \u0e1e\u0e34\u0e27\u0e23\u0e34\u0e1f\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e35 23 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130585\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e42\u0e1f\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130585 \u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e42\u0e1f\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e0d\u52d5\u7523 87\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19\u0e2a\u0e4c\u0e40\u0e1e\u0e25\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130623\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130623 \u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e0d\u52d5\u7523 87\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19\u0e2a\u0e4c\u0e40\u0e1e\u0e25\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130640\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130640 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 79110 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e23\u0e34\u0e1b\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e1a\u0e1a private tour \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e15\u0e39\u0e49\u0e23\u0e30\u0e14\u0e31\u0e1a vip \u0e41\u0e25\u0e30 luxury car \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 118\/41  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130682\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e44\u0e1f\u0e27\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130682 \u0e1a\u0e08.\u0e18\u0e19\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e44\u0e1f\u0e27\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e0d\u52d5\u7523 87\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19\u0e2a\u0e4c\u0e40\u0e1e\u0e25\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022758\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e22\u0e01\u0e27\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022758 \u0e1a\u0e08.\u0e2b\u0e22\u0e01\u0e27\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0a\u0e32 \u0e43\u0e1a\u0e0a\u0e32 \u0e1c\u0e07\u0e0a\u0e32 \u0e0a\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e0a\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e0a\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e0a\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e07\u0e0a\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e07\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0a\u0e07\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1614\/796  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022936\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e0b\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022936 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e0b\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 41002 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21, \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07,\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07,\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e20\u0e31\u0e22 \u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e32\u0e07\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32,\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22, \u0e07\u0e32\u0e19\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 (\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e07\u0e32\u0e19\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e15\u0e16\u0e38\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14) \u5efa\u8a2d 2122\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0185569000487\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e09\u0e25\u0e34\u0e21\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e40\u0e1a\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0185569000487 \u0e1a\u0e08.\u0e40\u0e09\u0e25\u0e34\u0e21\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e40\u0e1a\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 35102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0205569036154\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e38\u0e08\u0e08\u0e39 \u0e27\u0e34\u0e07\u0e2a\u0e4c(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036154 \u0e1a\u0e08.\u0e01\u0e38\u0e08\u0e08\u0e39 \u0e27\u0e34\u0e07\u0e2a\u0e4c(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 325\/67-70  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0745569007214\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007214 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1b\u0e25\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 80\/1099  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569012781\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47733\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47733\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012781 \u0e1a\u0e08.\u0e1a\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 4000000 47733 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e02\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e0a\u0e48\u0e2d\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49  \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/29  \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e48\u0e2d\u0e27\u0e31\u0e14\u0e09\u0e25\u0e2d\u0e07 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569128564\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e0a\u0e47\u0e2d\u0e1b\u0e42\u0e1b\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16291\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16291\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128564 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e0a\u0e47\u0e2d\u0e1b\u0e42\u0e1b\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 16291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e40\u0e40\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e40\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u88fd\u9020 2823\/3  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e32\u0e22\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128793\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e17\u0e2a\u0e42\u0e04 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128793 \u0e1a\u0e08. \u0e40\u0e17\u0e2a\u0e42\u0e04 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e2d\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 205  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 64 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128891\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e44\u0e27\u0e19\u0e4c \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128891 \u0e1a\u0e08.\u0e14\u0e35\u0e44\u0e27\u0e19\u0e4c \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 919\/249  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48\u0e40\u0e17\u0e23\u0e14\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129170\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129170 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (smart technology devices) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c iot (internet of thing) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15\u0e42\u0e2e\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 98\/4  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129251\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e25\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129251 \u0e1a\u0e08.\u0e0b\u0e35\u0e25\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 62023 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 92\/5  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e23\u0e18\u0e32\u0e19\u0e35 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022600\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e09\u0e07 \u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022600 \u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e19\u0e09\u0e07 \u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e01\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 168\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569036031\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e34\u0e2a \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036031 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e34\u0e2a \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 576\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036049\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e19\u0e17\u0e31\u0e25 \u0e23\u0e35\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e0b\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036049 \u0e1a\u0e08.\u0e41\u0e25\u0e19\u0e17\u0e31\u0e25 \u0e23\u0e35\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e0b\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01 (non-ferrous metals) \u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15) \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e33 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 189\/82  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e2d\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009122\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e1d\u0e39\u0e2b\u0e22\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009122 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e1d\u0e39\u0e2b\u0e22\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e25\u0e30\u0e23\u0e31\u0e07\u0e27\u0e31\u0e14 \u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e07\u0e32\u0e19\u0e01\u0e31\u0e19\u0e0b\u0e36\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e14\u0e01\u0e23\u0e48\u0e2d\u0e19 \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u5efa\u8a2d 887\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0435569001103\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e29\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001103 \u0e1a\u0e08.\u0e40\u0e21\u0e29\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 1111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0525569001625\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e42\u0e04\u0e25\u0e14\u0e23\u0e34\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001625 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e42\u0e04\u0e25\u0e14\u0e23\u0e34\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e14 \u0e04\u0e31\u0e48\u0e27 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e01\u0e31\u0e14\u0e40\u0e22\u0e47\u0e19 (cold drip \/ cold brew)  \u0e0a\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 60  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e44\u0e21\u0e15\u0e23\u0e35 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0775569002891\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e04\u0e42\u0e04\u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e15\u0e23\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002891 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e04\u0e42\u0e04\u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e15\u0e23\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 4000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e01\u0e32\u0e01\u0e43\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e02\u0e38\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0105569128165\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35 \u0e04\u0e25\u0e31\u0e1a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128165 \u0e1a\u0e08.\u0e27\u0e35 \u0e04\u0e25\u0e31\u0e1a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 4000000 70201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d \u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 109  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 50 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128301\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e48\u0e19\u0e25\u0e35\u0e48 \u0e40\u0e1f\u0e34\u0e48\u0e19\u0e25\u0e35\u0e48 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128301 \u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e48\u0e19\u0e25\u0e35\u0e48 \u0e40\u0e1f\u0e34\u0e48\u0e19\u0e25\u0e35\u0e48 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 4000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b  \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u88fd\u9020 1\/38  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e25\u0e33\u0e01\u0e2d\u0e44\u0e1c\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569025358\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e07\u0e1f\u0e32\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025358 \u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e07\u0e1f\u0e32\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 4000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (freight forwarder) \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 305\/112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009050\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e24\u0e01\u0e29\u0e4c\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009050 \u0e1a\u0e08.\u0e1e\u0e24\u0e01\u0e29\u0e4c\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 4000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e21\u0e40\u0e15\u0e47\u0e25 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 435\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002136\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e0a \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002136 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e0a \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 4000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e25\u0e33\u0e44\u0e22 \u0e21\u0e30\u0e02\u0e32\u0e21 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e21\u0e31\u0e19\u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e31\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e1c\u0e31\u0e01\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569127380\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127380 \u0e1a\u0e08.\u0e1a\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 46900 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/91  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e17\u0e27\u0e35\u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 2 \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 20 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 - \u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127541\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52293\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52293\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127541 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 52293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 72\/459  \u0e0b\u0e2d\u0e22 \u0e1a\u0e36\u0e07\u0e02\u0e27\u0e32\u0e071\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022227\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e48\u0e07\u0e0b\u0e35\u0e48  \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022227 \u0e1a\u0e08.\u0e40\u0e0b\u0e34\u0e48\u0e07\u0e0b\u0e35\u0e48  \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e17\u0e1b\u0e01\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e22\u0e37\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569035565\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035565 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 8\/100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035590\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e22\u0e32 \u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035590 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e22\u0e32 \u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 49\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0505569015201\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e2d\u0e2d\u0e42\u0e15\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015201 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e2d\u0e2d\u0e42\u0e15\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0835569012519\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012519 \u0e1a\u0e08.\u0e2d\u0e31\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u5bbf\u6cca\u30fb\u98f2\u98df 158\/97-98  \u0e16\u0e19\u0e19\u0e19\u0e32\u0e43\u0e19 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0865569001185\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u0e40\u0e2d.\u0e1e\u0e35.\u0e14\u0e35. \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001185 \u0e1a\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u0e40\u0e2d.\u0e1e\u0e35.\u0e14\u0e35. \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 4000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 278\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569035344\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21\u0e42\u0e21\u0e42\u0e21\u0e48 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035344 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21\u0e42\u0e21\u0e42\u0e21\u0e48 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 ks-136 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0403569002931\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002931 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c 2569-07-04 4000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 (energy storage system) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569126197\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e40\u0e27\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126197 \u0e1a\u0e08.\u0e25\u0e39\u0e40\u0e27\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 73102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e4d\u0e32\u0e2d\u0e32\u0e07, \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c111 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126367\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17 \u0e17\u0e34\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e14\u0e42\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126367 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17 \u0e17\u0e34\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e14\u0e42\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 283\/39,41  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e2e\u0e21\u0e40\u0e1e\u0e25\u0e2a \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 55(\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d13) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126413\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18\u0e40\u0e18\u0e34\u0e23\u0e4c\u0e19 \u0e01\u0e39\u0e23\u0e4c\u0e40\u0e21\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126413 \u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18\u0e40\u0e18\u0e34\u0e23\u0e4c\u0e19 \u0e01\u0e39\u0e23\u0e4c\u0e40\u0e21\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 27\/1   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e40\u0e2d 1\/1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 33 (\u0e41\u0e14\u0e07\u0e2d\u0e38\u0e14\u0e21) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022065\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022065 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b-028 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024840\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e48\u0e32\u0e19\u0e44\u0e21\u0e49\u0e44\u0e1c\u0e48 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024840 \u0e1a\u0e08.\u0e21\u0e48\u0e32\u0e19\u0e44\u0e21\u0e49\u0e44\u0e1c\u0e48 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e33\u0e19\u0e27\u0e13 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e23\u0e32\u0e04\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e27\u0e32\u0e14 \u0e17\u0e35\u0e48\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07 \u5efa\u8a2d 107\/120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035191\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e44\u0e15\u0e40\u0e01\u0e19 \u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035191 \u0e1a\u0e08.\u0e2a\u0e44\u0e15\u0e40\u0e01\u0e19 \u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 206\/148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035298\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e40\u0e08\u0e49\u0e32\u0e01\u0e31\u0e4b\u0e27\u0e08\u0e35\u0e49\u0e40\u0e08\u0e35\u0e22\u0e19\u0e08\u0e39\u0e4b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035298 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e40\u0e08\u0e49\u0e32\u0e01\u0e31\u0e4b\u0e27\u0e08\u0e35\u0e49\u0e40\u0e08\u0e35\u0e22\u0e19\u0e08\u0e39\u0e4b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e04\u0e23\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 292\/150  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e17\u0e23\u0e32\u0e22\u0e41\u0e01\u0e49\u0e27\u0e1a\u0e48\u0e2d\u0e27\u0e34\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0835569012438\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012438 \u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 4000000 58113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e2a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 160\/2  \u0e16\u0e19\u0e19\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569125263\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e25\u0e31\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e23\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125263 \u0e1a\u0e08.\u0e04\u0e32\u0e25\u0e31\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e23\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 4000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1296\/96  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021743\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e40\u0e1f\u0e34\u0e07 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021743 \u0e1a\u0e08.\u0e08\u0e39\u0e40\u0e1f\u0e34\u0e07 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 4000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e01\u0e34\u0e48\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021786\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e35\u0e22\u0e27  \u0e41\u0e2d\u0e1e\u0e1e\u0e32\u0e40\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021786 \u0e1a\u0e08.\u0e40\u0e01\u0e35\u0e22\u0e27  \u0e41\u0e2d\u0e1e\u0e1e\u0e32\u0e40\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 4000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01 \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48 \u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07 \u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 23 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569034992\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034992 \u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 4000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e14\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32(live commerce) \u0e15\u0e32\u0e21\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19shopee lazada \u0e2b\u0e23\u0e37\u0e2dtiktok shop \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 777  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035026\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e31\u0e15\u0e15\u0e32\u0e23\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035026 \u0e1a\u0e08.\u0e2a\u0e31\u0e15\u0e15\u0e32\u0e23\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 4000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 10\/86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035051\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74909\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74909\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035051 \u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 4000000 74909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 268\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035077\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e2b\u0e25\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035077 \u0e1a\u0e08.\u0e44\u0e2e\u0e2b\u0e25\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 4000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1e\u0e23\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569124569\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e40\u0e2b\u0e21\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124569 \u0e1a\u0e08.\u0e44\u0e17\u0e40\u0e2b\u0e21\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 17  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32- \u0e15\u0e23\u0e32\u0e14 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569024556\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e42\u0e01\u0e0a\u0e32\u0e23\u0e4c\u0e08 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024556 \u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e42\u0e01\u0e0a\u0e32\u0e23\u0e4c\u0e08 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 4000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 87\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034577\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22\u0e19\u0e17\u0e32\u0e14\u0e01\u0e49\u0e32\u0e1f\u0e39\u0e49\u0e14\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034577 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22\u0e19\u0e17\u0e32\u0e14\u0e01\u0e49\u0e32\u0e1f\u0e39\u0e49\u0e14\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 4000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 159\/272   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48 184 \u0e25\u0e27.25 \u0e21\u0e34.\u0e22.2557 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e40\u0e01\u0e25\u0e37\u0e2d 29\/1 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32-\u0e19\u0e32\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034658\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 804 - 805 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034658 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 804 - 805 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 4000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 453\/353  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034691\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e14\u0e27\u0e32\u0e22.\u0e01\u0e23\u0e35\u0e19 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":4000000,\"capital_display\":\"4,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034691 \u0e1a\u0e08.\u0e41\u0e0b\u0e14\u0e27\u0e32\u0e22.\u0e01\u0e23\u0e35\u0e19 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 4000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u5efa\u8a2d 55\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569143431\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e4a\u0e2d\u0e01\u0e0b\u0e4c \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":3500000,\"capital_display\":\"3,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143431 \u0e1a\u0e08.\u0e23\u0e4a\u0e2d\u0e01\u0e0b\u0e4c \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 3500000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e42\u0e22\u0e04\u0e30 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e22\u0e34\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u82b8\u8853\u30fb\u5a2f\u697d 789  \u0e16\u0e19\u0e19\u0e28\u0e32\u0e25\u0e32\u0e18\u0e23\u0e23\u0e21\u0e2a\u0e1e\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0845569010133\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":3500000,\"capital_display\":\"3,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010133 \u0e1a\u0e08.\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 3500000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 73\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569006437\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":3400000,\"capital_display\":\"3,400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006437 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 3400000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19-\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e32\u0e40\u0e21\u0e28\u0e27\u0e23\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0303569002788\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e0a\u0e40\u0e04 \u0e2d\u0e31\u0e0d\u0e0a\u0e25\u0e35\u0e01\u0e23 227\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3300000,\"capital_display\":\"3,300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002788 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e0a\u0e40\u0e04 \u0e2d\u0e31\u0e0d\u0e0a\u0e25\u0e35\u0e01\u0e23 227 2569-07-20 3300000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u5efa\u8a2d 102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0243569000697\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e31\u0e12. \u0e42\u0e1b\u0e23 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3100000,\"capital_display\":\"3,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000697 \u0e2b\u0e08.\u0e27\u0e31\u0e12. \u0e42\u0e1b\u0e23 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-16 3100000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 85\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0303569002702\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d1\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3010000,\"capital_display\":\"3,010,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002702 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d1 2569-07-13 3010000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e23\u0e27\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e1f\u0e25\u0e15 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e21\u0e19\u0e0a\u0e31\u0e19 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u4e0d\u52d5\u7523 58\/5-6  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0105569142931\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142931 \u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 3000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 827\/1  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 87 (\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142966\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e27\u0e4c\u0e40\u0e0b\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142966 \u0e1a\u0e08.\u0e42\u0e0a\u0e27\u0e4c\u0e40\u0e0b\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 3000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1d\u0e39\u0e07\u0e0a\u0e19 (crowd management) \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e35\u0e14 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 998\/3  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0405569007357\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e17\u0e35\u0e22\u0e39\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007357 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e17\u0e35\u0e22\u0e39\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 3000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e25\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 232\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0965569000595\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e1a\u0e19\u0e39 \u0e40\u0e1a\u0e19\u0e08\u0e32\u0e21\u0e34\u0e19  1448  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0965569000595 \u0e1a\u0e08.\u0e2d\u0e34\u0e1a\u0e19\u0e39 \u0e40\u0e1a\u0e19\u0e08\u0e32\u0e21\u0e34\u0e19  1448  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 3000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569142648\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142648 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 3000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 162  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028411\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028411 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 3000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 95\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0505569016860\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e04\u0e25\u0e4c\u0e21\u0e17\u0e39\u0e40\u0e01\u0e47\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016860 \u0e1a\u0e08.\u0e44\u0e04\u0e25\u0e4c\u0e21\u0e17\u0e39\u0e40\u0e01\u0e47\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 3000000 93112 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e43\u0e19\u0e23\u0e48\u0e21 (\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e32\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e41\u0e1a\u0e1a boulder) \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e21\u0e34\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u82b8\u8853\u30fb\u5a2f\u697d 129\/165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0745569008075\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e42\u0e2e\u0e21 \u0e19\u0e4a\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008075 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e42\u0e2e\u0e21 \u0e19\u0e4a\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e40\u0e40\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 129\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569006364\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22 \u0e1f\u0e39\u0e49\u0e14 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e2d\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006364 \u0e1a\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22 \u0e1f\u0e39\u0e49\u0e14 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e2d\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 3000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0115569025111\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025111 \u0e1a\u0e08.\u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 3000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 (\u0e41\u0e17\u0e47\u0e01\u0e0b\u0e35\u0e48) \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e04\u0e19\u0e02\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e19\u0e02\u0e31\u0e1a \u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1937  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016819\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e30\u0e15\u0e34\u0e08\u0e39\u0e14 \u0e42\u0e2d\u0e40\u0e2d\u0e0b\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016819 \u0e1a\u0e08.\u0e25\u0e30\u0e15\u0e34\u0e08\u0e39\u0e14 \u0e42\u0e2d\u0e40\u0e2d\u0e0b\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 3000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 310  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e44\u0e2d\u0e04\u0e2d\u0e19 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e21\u0e13\u0e35\u0e19\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569141919\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e40\u0e2d\u0e04\u0e2d\u0e21 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27103\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27103\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141919 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e40\u0e2d\u0e04\u0e2d\u0e21 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 27103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e19\u0e49\u0e33 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e31\u0e14\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 33\/4  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30\u0e44\u0e19\u0e19\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2a \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 34 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0145569004946\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e1e\u0e35 \u0e1f\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004946 \u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e1e\u0e35 \u0e1f\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 77109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30 \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 222\/344  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001785\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e4a\u0e01\u0e1a\u0e2d\u0e2a\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001785 \u0e1a\u0e08.\u0e1a\u0e34\u0e4a\u0e01\u0e1a\u0e2d\u0e2a\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039269\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e15\u0e49\u0e32\u0e44\u0e09 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039269 \u0e1a\u0e08.\u0e1f\u0e32\u0e15\u0e49\u0e32\u0e44\u0e09 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e27\u0e19 \u5efa\u8a2d 55\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009971\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e2b\u0e34\u0e23\u0e31\u0e0d \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 1967  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52219\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52219\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009971 \u0e1a\u0e08.\u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e2b\u0e34\u0e23\u0e31\u0e0d \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 1967  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 52219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e01\u0e32\u0e23\u0e08\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569010015\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c\u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86902\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86902\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010015 \u0e1a\u0e08.\u0e04\u0e27\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c\u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 86902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u533b\u7642\u30fb\u798f\u7949 109\/4-5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0375569000418\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e22\u0e39 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e0b\u0e4c\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0375569000418 \u0e1a\u0e08.\u0e40\u0e2d\u0e22\u0e39 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e0b\u0e4c\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u5efa\u8a2d 190  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0453569001110\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e37\u0e0a\u0e1c\u0e25\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001110 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e37\u0e0a\u0e1c\u0e25 2569-07-27 3000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0525569001781\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c  \u0e40\u0e01\u0e25\u0e0b\u0e14\u0e4c \u0e40\u0e19\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001781 \u0e1a\u0e08.\u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c  \u0e40\u0e01\u0e25\u0e0b\u0e14\u0e4c \u0e40\u0e19\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e25\u0e47\u0e1a\u0e21\u0e37\u0e2d\u0e40\u0e25\u0e47\u0e1a\u0e40\u0e17\u0e49\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 176\/2  \u0e16\u0e19\u0e19\u0e08\u0e32\u0e21\u0e40\u0e17\u0e27\u0e35 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569006305\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c  \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e2d\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006305 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c  \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e2d\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 3000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e01\u0e38\u0e49\u0e07 \u0e2b\u0e2d\u0e22 \u0e1b\u0e39 \u0e1b\u0e25\u0e32 \u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0215569009947\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e08\u0e35\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009947 \u0e1a\u0e08.\u0e2d\u0e35\u0e08\u0e35\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 3000000 71102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 4\/78  \u0e0b\u0e2d\u0e22 \u0e41\u0e2b\u0e25\u0e21\u0e01\u0e23\u0e30\u0e17\u0e37\u0e2d \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0425569000603\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000603 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 3000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569139612\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e0a\u0e01\u0e32\u0e22\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139612 \u0e1a\u0e08.\u0e40\u0e27\u0e0a\u0e01\u0e32\u0e22\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 3000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 136\/13, 136\/14  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140921\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e34\u0e19\u0e23\u0e1e\u0e23\u0e2b\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140921 \u0e1a\u0e08.\u0e2e\u0e34\u0e19\u0e23\u0e1e\u0e23\u0e2b\u0e21 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 3000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23 \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 82\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024742\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e04\u0e04\u0e34\u0e40\u0e17\u0e47\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024742 \u0e1a\u0e08.\u0e41\u0e21\u0e04\u0e04\u0e34\u0e40\u0e17\u0e47\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 3000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 555\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569004031\",\"name_th\":\"\u0e1a\u0e08.888 \u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004031 \u0e1a\u0e08.888 \u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 3000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c (franchise) \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 346\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0425569000581\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e17\u0e2d\u0e07\u0e21\u0e32\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000581 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e17\u0e2d\u0e07\u0e21\u0e32\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 3000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0555569000645\",\"name_th\":\"\u0e1a\u0e08.\u0e18.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000645 \u0e1a\u0e08.\u0e18.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 3000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007966\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e40\u0e04\u0e2d \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007966 \u0e1a\u0e08.\u0e44\u0e25\u0e40\u0e04\u0e2d \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 3000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569138837\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138837 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 17   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a3 \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e23.9 \u0e0b.87 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139329\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e27\u0e32\u0e23\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139329 \u0e1a\u0e08.\u0e18\u0e32\u0e27\u0e32\u0e23\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e40\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e40\u0e40\u0e25\u0e30\u0e40\u0e40\u0e01\u0e49\u0e44\u0e02 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e0b\u0e2d\u0e1f\u0e40\u0e40\u0e27\u0e23\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e1b\u0e23\u0e40\u0e40\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e09\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e27\u0e35\u0e14\u0e35\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e17\u0e22\u0e38\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e40\u0e2a\u0e14\u0e07\u0e20\u0e32\u0e1e\u0e40\u0e40\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e27\u0e34\u0e17\u0e22\u0e38\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e40\u0e40\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e40\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 9\/197  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e0a\u0e1b\u0e23\u0e30\u0e0a\u0e32 4 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139337\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e34\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139337 \u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e34\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d \u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 (passport) \u0e27\u0e35\u0e0b\u0e48\u0e32 (visa) \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e48\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e39\u0e15 \u0e2a\u0e16\u0e32\u0e19\u0e01\u0e07\u0e2a\u0e38\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 20  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024459\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e23\u0e31\u0e2a\u0e01\u0e4c\u0e01\u0e23 \u0e01\u0e25\u0e01\u0e32\u0e23 89 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024459 \u0e1a\u0e08.\u0e27\u0e23\u0e31\u0e2a\u0e01\u0e4c\u0e01\u0e23 \u0e01\u0e25\u0e01\u0e32\u0e23 89 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e09\u0e35\u0e14\u0e25\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33  \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e19\u0e49\u0e33\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e23\u0e16\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e15\u0e34\u0e14\u0e41\u0e02\u0e19\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32 \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e14\u0e31\u0e49\u0e21 \u0e23\u0e16\u0e40\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32  \u0e23\u0e16\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e31\u0e48\u0e07\u0e02\u0e31\u0e1a \u0e23\u0e16\u0e1a\u0e14\u0e25\u0e49\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e23\u0e16\u0e1a\u0e14\u0e25\u0e49\u0e2d\u0e22\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e25\u0e32\u0e01\u0e08\u0e39\u0e07 \u0e23\u0e16\u0e15\u0e31\u0e01\u0e2b\u0e19\u0e49\u0e32 \u0e23\u0e16\u0e40\u0e02\u0e47\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e07\u0e01\u0e27\u0e32\u0e14 \u0e23\u0e16\u0e15\u0e34\u0e14\u0e41\u0e02\u0e19\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04\u0e17\u0e49\u0e32\u0e22\u0e23\u0e16  \u0e23\u0e16\u0e0b\u0e48\u0e2d\u0e21\u0e16\u0e19\u0e19\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e32\u0e19\u0e15\u0e48\u0e33 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e07\u0e40\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e16\u0e22\u0e01\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 \u0e23\u0e16\u0e15\u0e23\u0e27\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e1a\u0e1a\u0e1b\u0e34\u0e04\u0e2d\u0e31\u0e1e  \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e40\u0e17\u0e17\u0e49\u0e32\u0e22 \u0e23\u0e16\u0e42\u0e04\u0e21\u0e44\u0e1f \u0e23\u0e16\u0e1a\u0e14\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e0a\u0e19\u0e34\u0e14\u0e25\u0e49\u0e2d\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e49\u0e2d\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e25\u0e49\u0e2d\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e49\u0e2d\u0e22\u0e32\u0e07 \u0e23\u0e16\u0e14\u0e39\u0e14\u0e25\u0e49\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 998\/82  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569038611\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 701 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038611 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 701 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 453\/331  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038661\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e22\u0e32\u0e21\u0e32\u0e14\u0e30  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038661 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e22\u0e32\u0e21\u0e32\u0e14\u0e30  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30 \u0e2d\u0e30\u0e44\u0e2b\u0e23\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e23\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 3\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 7 \u0e16\u0e19\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e04\u0e38\u0e49\u0e07-\u0e2b\u0e19\u0e2d\u0e07\u0e23\u0e35 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002915\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002915 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-23 3000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e42\u0e2d\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e33\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0425569000565\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e14\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52101\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52101\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000565 \u0e1a\u0e08.\u0e23\u0e14\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 52101 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 234  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0745569007834\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007834 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 3000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0763569000331\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e35\u0e17\u0e31\u0e15 2555 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0763569000331 \u0e2b\u0e08.\u0e18\u0e35\u0e17\u0e31\u0e15 2555 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-23 3000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e14\u0e34\u0e19 \u0e07\u0e32\u0e19\u0e02\u0e38\u0e14 \u0e07\u0e32\u0e19\u0e16\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e02\u0e38\u0e14\u0e04\u0e39 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2b\u0e34\u0e19 \u5efa\u8a2d 16\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569138012\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e192 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138012 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e192 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 3000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c (software license) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1108\/31  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0305569007625\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 2001 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007625 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 2001 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 3000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u4e0d\u52d5\u7523 768\/3  \u0e16\u0e19\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e23\u0e07\u0e04\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0463569000776\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 1996\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000776 \u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 1996 2569-07-22 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 70  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0655569002370\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35.\u0e40\u0e07\u0e34\u0e19\u0e14\u0e48\u0e27\u0e19 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002370 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35.\u0e40\u0e07\u0e34\u0e19\u0e14\u0e48\u0e27\u0e19 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 3000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e07\u0e34\u0e19\u0e01\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u91d1\u878d\u30fb\u4fdd\u967a 180\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0135569022553\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e01\u0e49\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022553 \u0e1a\u0e08.\u0e40\u0e0b\u0e01\u0e49\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 3000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e01\u0e48\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e08\u0e47\u0e1a\u0e1b\u0e48\u0e27\u0e22 \u533b\u7642\u30fb\u798f\u7949 801\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1972 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004776\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e32 \u0e42\u0e19\u0e40\u0e27\u0e19\u0e15\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004776 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e32 \u0e42\u0e19\u0e40\u0e27\u0e19\u0e15\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 3000000 46691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0405569007004\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e42\u0e27\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007004 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e42\u0e27\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 3000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0445569001740\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001740 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 3000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a \u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32  \u0e0a\u0e38\u0e14\u0e40\u0e14\u0e47\u0e01 \u0e0a\u0e38\u0e14\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 267  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0105569136117\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e41\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66301\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66301\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136117 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e41\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 66301 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e19 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e2b\u0e19\u0e35\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e1a\u0e31\u0e15\u0e23\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e15\u0e31\u0e4b\u0e27\u0e40\u0e07\u0e34\u0e19 \u0e04\u0e25\u0e31\u0e07 \u0e15\u0e31\u0e4b\u0e27\u0e41\u0e25\u0e01\u0e40\u0e07\u0e34\u0e19 \u0e15\u0e31\u0e4b\u0e27\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e1a\u0e31\u0e15\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e14\u0e46 \u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 66  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 24\/5 (\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e35\u0e0a\u0e32) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136290\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e2a\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136290 \u0e1a\u0e08.\u0e13\u0e2a\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e40\u0e2b\u0e23\u0e35\u0e0d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e1a\u0e1c\u0e49\u0e32\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e0d \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 616\/14  \u0e16\u0e19\u0e19\u0e40\u0e15\u0e0a\u0e30\u0e27\u0e19\u0e34\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027369\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e22\u0e30 \u0e44\u0e23\u0e2a\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027369 \u0e1a\u0e08.\u0e2d\u0e32\u0e22\u0e30 \u0e44\u0e23\u0e2a\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e14\u0e34\u0e19 \u0e07\u0e32\u0e19\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 157\/49  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 54 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022294\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e04\u0e25\u0e32\u0e2a \u0e17\u0e35\u0e08\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022294 \u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e04\u0e25\u0e32\u0e2a \u0e17\u0e35\u0e08\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 47640 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/18  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e13\u0e32\u0e2a\u0e34\u0e23\u0e34 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0165569001661\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e41\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93120\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93120\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001661 \u0e1a\u0e08.\u0e23\u0e35\u0e41\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 93120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u82b8\u8853\u30fb\u5a2f\u697d 65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038025\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e25\u0e35\u0e17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038025 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e25\u0e35\u0e17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 25\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0415569003823\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e21\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003823 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e21\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39-\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e27  \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e48\u0e40\u0e40\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0425569000531\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000531 \u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 185  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e192250 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0465569000891\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e24\u0e29\u0e13\u0e32  \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82920\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82920\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000891 \u0e1a\u0e08.\u0e01\u0e24\u0e29\u0e13\u0e32  \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 82920 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e42\u0e25\u0e42\u0e01\u0e49 \u0e09\u0e25\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e1a\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 488\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0525569001684\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21 2026  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001684 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21 2026  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 456  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013370\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e25\u0e04\u0e2d\u0e25 \u0e44\u0e14\u0e19\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013370 \u0e1a\u0e08.\u0e42\u0e25\u0e04\u0e2d\u0e25 \u0e44\u0e14\u0e19\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 3000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 126  \u0e16\u0e19\u0e19\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0323569000564\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e38\u0e13\u0e21\u0e32\u0e2a\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000564 \u0e2b\u0e08.\u0e04\u0e38\u0e13\u0e21\u0e32\u0e2a\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-18 3000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 305  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0185569000495\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e21\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0185569000495 \u0e1a\u0e08.\u0e18\u0e19\u0e21\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 3000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 465  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0225569002292\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e35\u0e40\u0e04\u0e1e\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002292 \u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e35\u0e40\u0e04\u0e1e\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 71\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0475569001618\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35.\u0e44\u0e19\u0e25\u0e4c \u0e17\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001618 \u0e1a\u0e08.\u0e08\u0e35.\u0e44\u0e19\u0e25\u0e4c \u0e17\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 3000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000964\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e42\u0e21\u0e48 \u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96305\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96305\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000964 \u0e1a\u0e08.\u0e0b\u0e39\u0e42\u0e21\u0e48 \u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 3000000 96305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e2d\u0e1a\u0e15\u0e31\u0e27 \u0e2d\u0e1a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2d\u0e1a\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0905569005872\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e27\u0e2d\u0e0a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005872 \u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e27\u0e2d\u0e0a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 3000000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 76\/3  \u0e0b\u0e2d\u0e22 10 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569134360\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e14\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134360 \u0e1a\u0e08.\u0e42\u0e14\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 191\/70  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e35\u0e17\u0e35\u0e44\u0e2d \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 14 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134530\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17 \u0e2d\u0e31\u0e1e \u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134530 \u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17 \u0e2d\u0e31\u0e1e \u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 74200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b  \u0e25\u0e49\u0e32\u0e07  \u0e2d\u0e31\u0e14  \u0e02\u0e22\u0e32\u0e22\u0e23\u0e39\u0e1b  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 37  \u0e16\u0e19\u0e19\u0e42\u0e01\u0e2a\u0e38\u0e21\u0e23\u0e27\u0e21\u0e43\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0145569004679\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23-\u0e1e\u0e23\u0e1b\u0e34\u0e22\u0e30 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46106\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46106\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004679 \u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23-\u0e1e\u0e23\u0e1b\u0e34\u0e22\u0e30 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 46106 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 159\/9  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e23\u0e35\u0e19\u0e14\u0e4c\u0e42\u0e2e\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0405569006890\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006890 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e27\u0e32\u0e07\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016002\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016002 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 141\/5   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s11 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004608\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e30\u0e13\u0e34\u0e10 \u0e42\u0e1b\u0e23\u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004608 \u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e30\u0e13\u0e34\u0e10 \u0e42\u0e1b\u0e23\u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 565  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0715569002671\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10795\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10795\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002671 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 10795 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u88fd\u9020 135\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007222\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48\u0e44\u0e2b\u0e271155 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007222 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48\u0e44\u0e2b\u0e271155 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 3000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 247  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0105569133703\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e40\u0e14\u0e22\u0e4c 117 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133703 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e40\u0e14\u0e22\u0e4c 117 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 270,272,274  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133932\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2021 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133932 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2021 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 56102 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e19\u0e41\u0e1c\u0e07\u0e25\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 144\/3  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 40 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134025\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134025 \u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32\u0e07\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22\u0e01\u0e23\u0e23\u0e21\u0e27\u0e34\u0e18\u0e35\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/1  \u0e16\u0e19\u0e19\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026664\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e17\u0e47\u0e01\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026664 \u0e1a\u0e08.\u0e41\u0e17\u0e47\u0e01\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19  \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e22\u0e49\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 77\/563  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003106\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 168\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003106 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 168 2569-07-15 3000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 88\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0405569006822\",\"name_th\":\"\u0e1a\u0e08.159 \u0e2d\u0e2d\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006822 \u0e1a\u0e08.159 \u0e2d\u0e2d\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e31\u0e01 \u0e23\u0e49\u0e32\u0e19\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07 (self-service laundry) \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e1a\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01 \u0e2d\u0e1a \u0e23\u0e35\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 159\/260  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003227\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e0a\u0e34\u0e01\u0e40\u0e01\u0e49\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003227 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e0a\u0e34\u0e01\u0e40\u0e01\u0e49\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e44\u0e01\u0e48 \u0e2b\u0e21\u0e39 \u0e40\u0e1b\u0e47\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 369\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003235\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003235 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e35\u0e04\u0e48\u0e32 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e04\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/1  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e2b\u0e31\u0e01 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0865569001258\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e04\u0e2d\u0e23\u0e4c\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001258 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e04\u0e2d\u0e23\u0e4c\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 3000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 176\/36  \u0e0b\u0e2d\u0e22 \u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c 2 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569133151\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e23\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35301\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35301\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133151 \u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e23\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 3000000 35301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 230  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0405569006784\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e27\u0e32 \u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10771\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10771\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006784 \u0e1a\u0e08.\u0e40\u0e17\u0e27\u0e32 \u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 3000000 10771 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1e\u0e23\u0e34\u0e01\u0e41\u0e01\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e1c\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e1e\u0e23\u0e34\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e1e\u0e23\u0e34\u0e01\u0e1b\u0e48\u0e19 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e02\u0e49\u0e32\u0e27\u0e04\u0e31\u0e48\u0e27 \u88fd\u9020 192  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0715569002620\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e0b\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002620 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e0b\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 3000000 64201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 (holding company) \u91d1\u878d\u30fb\u4fdd\u967a 178\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0743569000994\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e0a\u0e0a\u0e1e\u0e23 \u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000994 \u0e2b\u0e08.\u0e23\u0e31\u0e0a\u0e0a\u0e1e\u0e23 \u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01 2569-07-14 3000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 171\/166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0913569000291\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e18\u0e31\u0e19\u0e22\u0e1e\u0e37\u0e0a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0913569000291 \u0e2b\u0e08.\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e18\u0e31\u0e19\u0e22\u0e1e\u0e37\u0e0a 2569-07-14 3000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 211  \u0e16\u0e19\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0913569000305\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0913569000305 \u0e2b\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27 2569-07-14 3000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569132294\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132294 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 71102 1.\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e13 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e07\u0e01\u0e4a\u0e32\u0e0b (gas turbines) \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 388  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e01\u0e40\u0e0a\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e22\u0e39\u0e19\u0e34\u0e152901-2904 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 29 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132308\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2010 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132308 \u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2010 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 47524 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 136\/328  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 20 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026346\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e28\u0e27 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026346 \u0e1a\u0e08.\u0e2d\u0e31\u0e28\u0e27 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 80\/184  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002209\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e14\u0e35\u0e1e\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002209 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e14\u0e35\u0e1e\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007242\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e42\u0e13\u0e21\u0e32 \u0e23\u0e35\u0e08\u0e34\u0e2a \u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007242 \u0e1a\u0e08.\u0e2d\u0e42\u0e13\u0e21\u0e32 \u0e23\u0e35\u0e08\u0e34\u0e2a \u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 66\/5  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e15 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0415569003602\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e35\u0e43\u0e2b\u0e0d\u0e48 \u0e44\u0e2d\u0e17\u0e35 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003602 \u0e1a\u0e08.\u0e2b\u0e21\u0e35\u0e43\u0e2b\u0e0d\u0e48 \u0e44\u0e2d\u0e17\u0e35 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 489\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e02\u0e2d\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569015782\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1b\u0e31\u0e4a\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015782 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1b\u0e31\u0e4a\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e15\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e21\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e15\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u88fd\u9020 126\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015791\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e35\u0e19 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015791 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e35\u0e19 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 86101 \u0e15\u0e23\u0e27\u0e08\u0e42\u0e23\u0e04\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e42\u0e14\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e42\u0e23\u0e04\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d \u0e42\u0e23\u0e04\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07 \u0e28\u0e31\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u533b\u7642\u30fb\u798f\u7949 321  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015804\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e07\u0e22\u0e32 \u0e40\u0e21\u0e14\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015804 \u0e1a\u0e08.\u0e27\u0e07\u0e22\u0e32 \u0e40\u0e21\u0e14\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e42\u0e23\u0e04\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u533b\u7642\u30fb\u798f\u7949 161\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0815569002092\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e1e\u0e19\u0e21\u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002092 \u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e1e\u0e19\u0e21\u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 3000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0105569132022\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e15\u0e32\u0e23\u0e2d\u0e2a \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132022 \u0e1a\u0e08.\u0e04\u0e35\u0e15\u0e32\u0e23\u0e2d\u0e2a \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 3000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 69\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0493569000393\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e34\u0e22\u0e32\u0e01\u0e23 9 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0493569000393 \u0e2b\u0e08.\u0e1b\u0e23\u0e34\u0e22\u0e32\u0e01\u0e23 9 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-12 3000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 24\/9  \u0e16\u0e19\u0e19\u0e15\u0e32\u0e14\u0e41\u0e04\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569131921\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e04\u0e14\u0e4c \u0e40\u0e17\u0e40\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131921 \u0e1a\u0e08.\u0e44\u0e04\u0e14\u0e4c \u0e40\u0e17\u0e40\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 3000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e1f (hot pot) \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c\u0e40\u0e1a\u0e2a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e21\u0e31\u0e07\u0e2a\u0e27\u0e34\u0e23\u0e31\u0e15\u0e34 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 (delivery) \u5bbf\u6cca\u30fb\u98f2\u98df 3654   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a102 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023096\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e2d\u0e34\u0e49\u0e07 \u0e40\u0e1e\u0e25\u0e2a\u0e40\u0e0b\u0e2a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58201\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58201\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023096 \u0e1a\u0e08.\u0e42\u0e01\u0e2d\u0e34\u0e49\u0e07 \u0e40\u0e1e\u0e25\u0e2a\u0e40\u0e0b\u0e2a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 3000000 58201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e40\u0e01\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e21 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19  \u0e2a\u0e37\u0e48\u0e2d\u0e41\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 (publisher)  \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 90\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 129 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0455569001421\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e19\u0e34\u0e25\u0e25\u0e32\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01193\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01193\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001421 \u0e1a\u0e08.\u0e27\u0e32\u0e19\u0e34\u0e25\u0e25\u0e32\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 3000000 01193 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 140  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e27\u0e31\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e19\u0e17\u0e2d\u0e07-\u0e2b\u0e19\u0e2d\u0e07\u0e1e\u0e2d\u0e01 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569007315\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d.\u0e1a\u0e35.(1990) \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007315 \u0e2b\u0e08.\u0e40\u0e2d.\u0e1a\u0e35.(1990) \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-10 3000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 216\/34  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131093\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e2a\u0e1b\u0e32\u0e22365 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131093 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e2a\u0e1b\u0e32\u0e22365 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 3000000 96309 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e25\u0e02\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 15  \u0e0b\u0e2d\u0e22 45 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131191\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e1f\u0e23\u0e2d\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46316\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46316\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131191 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e1f\u0e23\u0e2d\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 3000000 46316 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e44\u0e02\u0e48\u0e2a\u0e14 \u0e44\u0e02\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/315  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e2113(\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e31\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e2f3\u0e1c\u0e31\u0e071) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569036626\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e04\u0e40\u0e04\u0e34\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036626 \u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e04\u0e40\u0e04\u0e34\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 3000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e02\u0e2d\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e07 (lot) \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e1a\u0e34\u0e01\u0e14\u0e32\u0e15\u0e49\u0e32 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e15\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 70\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0635569001420\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e49\u0e32\u0e44\u0e14\u0e19\u0e32\u0e42\u0e21\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001420 \u0e1a\u0e08.\u0e40\u0e1f\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e49\u0e32\u0e44\u0e14\u0e19\u0e32\u0e42\u0e21\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 3000000 45201 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e44\u0e14\u0e19\u0e32\u0e42\u0e21 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 414  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0103569007285\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007285 \u0e2b\u0e08.\u0e08\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 2569-07-09 3000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e27\u0e19\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e2a\u0e27\u0e19\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e27\u0e19\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 16\/1  \u0e0b\u0e2d\u0e22 \u0e41\u0e2a\u0e21\u0e14\u0e3325 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129455\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129455 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269  \u0e16\u0e19\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129684\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129684 \u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e04\u0e25\u0e37\u0e48\u0e19\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e04\u0e25\u0e37\u0e48\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u533b\u7642\u30fb\u798f\u7949 99\/230  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130330\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130330 \u0e1a\u0e08.\u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e21\u0e19\u0e18\u0e32\u0e15\u0e38\u0e2f \u0e41\u0e22\u0e01 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130500\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e27\u0e4c\u0e19\u0e48\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46634\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46634\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130500 \u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e27\u0e4c\u0e19\u0e48\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 46634 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e27\u0e19 \u0e15\u0e39\u0e49\u0e2d\u0e1a\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e15\u0e39\u0e49\u0e2d\u0e1a\u0e40\u0e0b\u0e32\u0e27\u0e4c\u0e19\u0e48\u0e32 \u0e15\u0e49\u0e39\u0e2d\u0e1a\u0e40\u0e0b\u0e32\u0e27\u0e4c\u0e19\u0e48\u0e32\u0e2d\u0e34\u0e19\u0e1f\u0e32\u0e40\u0e23\u0e04 \u0e01\u0e4a\u0e2d\u0e01\u0e19\u0e49\u0e33 \u0e1d\u0e31\u0e01\u0e1a\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e1b\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 408  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e40\u0e1e\u0e25\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 408\/18 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130607\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e04\u0e42\u0e19\u0e41\u0e04\u0e23\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130607 \u0e1a\u0e08.\u0e40\u0e17\u0e04\u0e42\u0e19\u0e41\u0e04\u0e23\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 18\/253  \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569025943\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e01\u0e23\u0e38\u0e4a\u0e1b 888 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025943 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e01\u0e23\u0e38\u0e4a\u0e1b 888 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e19\u0e17\u0e4c\u0e13\u0e34\u0e0a\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003698\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e27\u0e34\u0e2a\u0e40\u0e19 \u0e44\u0e21\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"07300\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"07300\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003698 \u0e1a\u0e08.\u0e20\u0e32\u0e27\u0e34\u0e2a\u0e40\u0e19 \u0e44\u0e21\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 07300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e41\u0e23\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u9271\u696d\u30fb\u63a1\u77f3 555  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0315569001856\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e42\u0e1b\u0e23\u0e40\u0e17\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001856 \u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e42\u0e1b\u0e23\u0e40\u0e17\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 222\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569001864\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2b\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e19\u0e32\u0e42\u0e1e\u0e18\u0e34\u0e4c 1989 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001864 \u0e1a\u0e08.\u0e1e\u0e23\u0e2b\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e19\u0e32\u0e42\u0e1e\u0e18\u0e34\u0e4c 1989 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0335569001121\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001121 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e17\u0e31\u0e25\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 176  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569001854\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e1e\u0e37\u0e0a\u0e1c\u0e25\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001854 \u0e2b\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e1e\u0e37\u0e0a\u0e1c\u0e25 2569-07-09 3000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003131\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003131 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0475569001464\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e08\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001464 \u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e08\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2d\u0e17\u0e35\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 754  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015588\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e15\u0e23\u0e27\u0e35 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015588 \u0e1a\u0e08.\u0e42\u0e0a\u0e15\u0e23\u0e27\u0e35 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1c\u0e2a\u0e21\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e1c\u0e48\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e17\u0e48\u0e2d\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e2d\u0e34\u0e10\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e1a\u0e23\u0e34\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 456  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0715569002531\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002531 \u0e1a\u0e08.\u0e1e\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e02\u0e27\u0e14 \u0e41\u0e01\u0e49\u0e27 \u0e42\u0e25\u0e2b\u0e30\u0e15\u0e48\u0e32\u0e07\u0e46 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 200\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0763569000307\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c999\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0763569000307 \u0e2b\u0e08.\u0e27\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c999 2569-07-09 3000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 16\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0905569005589\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35 \u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005589 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35 \u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 3000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35  \u0e0b\u0e2d\u0e22 5 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e19\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569128645\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19 \u0e40\u0e17\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128645 \u0e1a\u0e08.\u0e27\u0e34\u0e19 \u0e40\u0e17\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 , \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 , \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 201\/106  \u0e0b\u0e2d\u0e22 \u0e2d\u0e22\u0e39\u0e48\u0e27\u0e34\u0e17\u0e22\u0e32 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128726\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128726 \u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25 \u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 111\/23  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128912\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52299\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52299\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128912 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 52299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (electric vehicle charging station) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e2a\u0e25\u0e31\u0e1a (ac) \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e15\u0e23\u0e07 (dc) \u904b\u8f38\u30fb\u7269\u6d41 18\/72  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 19\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129030\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e22\u0e27\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129030 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e22\u0e27\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 202  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e39\u0e1a\u0e34\u0e25\u0e35\u0e48 \u0e40\u0e1e\u0e23\u0e2a\u0e17\u0e35\u0e08 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a304 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129102\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e30\u0e42\u0e19\u0e04\u0e31\u0e21 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129102 \u0e1a\u0e08.\u0e04\u0e30\u0e42\u0e19\u0e04\u0e31\u0e21 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (logistics management) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19 (supply chain management) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 725  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e42\u0e17\u0e23  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 176 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0363569000858\",\"name_th\":\"\u0e2b\u0e08.999 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000858 \u0e2b\u0e08.999 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e4c 2569-07-08 3000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e25\u0e33\u0e1b\u0e2d\u0e41\u0e14\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0453569001004\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e1e\u0e23\u0e0a\u0e31\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001004 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e1e\u0e23\u0e0a\u0e31\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-08 3000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0505569015391\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015391 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 56102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0b\u0e38\u0e49\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e16\u0e40\u0e02\u0e47\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e39\u0e18\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e35\u0e2d\u0e2d\u0e2a \u0e40\u0e04\u0e32\u0e19\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e38\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e13 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e22\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e48\u0e19 \u0e1b\u0e23\u0e38\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e2a\u0e31\u0e48\u0e07\u0e08\u0e2d\u0e07\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 4  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0745569007150\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e15\u0e07\u0e44\u0e17\u0e22 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"03112\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"03112\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007150 \u0e1a\u0e08.\u0e41\u0e15\u0e07\u0e44\u0e17\u0e22 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 03112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e30\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14  \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e49\u0e38\u0e07 \u0e2b\u0e2d\u0e22 \u0e1b\u0e39\u0e1b\u0e25\u0e32 \u0e44\u0e21\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 99\/71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569012632\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012632 \u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 3000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 99\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569128092\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e41\u0e1e\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128092 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e41\u0e1e\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 3000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 (information technology) \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 1  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 79 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569020879\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e17\u0e35 \u0e1f\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020879 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e17\u0e35 \u0e1f\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 3000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569035671\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035671 \u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 3000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e35\u0e49\u0e22\u0e32\u0e07 \u0e40\u0e28\u0e29\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e08\u0e32\u0e01\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 133  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569001954\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e2b\u0e34\u0e23\u0e31\u0e13\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001954 \u0e1a\u0e08.\u0e20\u0e39\u0e2b\u0e34\u0e23\u0e31\u0e13\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 3000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 208\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0435569001081\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e41\u0e25\u0e01\u0e40\u0e07\u0e34\u0e19 \u0e42\u0e2d\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001081 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e41\u0e25\u0e01\u0e40\u0e07\u0e34\u0e19 \u0e42\u0e2d\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 3000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e2d\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 925  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569127347\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e42\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127347 \u0e1a\u0e08.\u0e27\u0e35\u0e42\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 88  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1b\u0e32\u0e42\u0e0b\u0e48\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 12-a04 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127428\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127428 \u0e1a\u0e08.\u0e27\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/2  \u0e0b\u0e2d\u0e22 \u0e41\u0e2a\u0e21\u0e14\u0e33 17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022278\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e27\u0e19\u0e40\u0e04\u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17091\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17091\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022278 \u0e1a\u0e08.\u0e41\u0e27\u0e19\u0e40\u0e04\u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 17091 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0a\u0e33\u0e23\u0e30\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e34\u0e0a\u0e0a\u0e39 \u88fd\u9020 347\/68  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569035557\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e14\u0e35\u0e21\u0e32\u0e23\u0e4c\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035557 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e14\u0e35\u0e21\u0e32\u0e23\u0e4c\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 165\/543  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569006971\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e13\u0e20\u0e31\u0e17\u0e23\u0e4c 2025 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006971 \u0e1a\u0e08.\u0e1e\u0e34\u0e13\u0e20\u0e31\u0e17\u0e23\u0e4c 2025 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 344\/89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0345569003034\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35\u0e14\u0e35 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003034 \u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35\u0e14\u0e35 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e25\u0e21 \u0e01\u0e31\u0e07\u0e2b\u0e31\u0e19\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 150  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569004398\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e19\u0e0b\u0e4c \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004398 \u0e2b\u0e08.\u0e44\u0e19\u0e0b\u0e4c \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-06 3000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 92\/11  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e1b\u0e34\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0775569002875\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47735\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47735\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002875 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 47735 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e41\u0e01\u0e4a\u0e2a \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 239  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0825569001096\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001096 \u0e1a\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 13\/26  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07 5 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569012501\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 (\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e17\u0e32\u0e27\u0e19\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012501 \u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 (\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e17\u0e32\u0e27\u0e19\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u533b\u7642\u30fb\u798f\u7949 64\/133-134  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0955569000528\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e48\u0e32\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000528 \u0e1a\u0e08.\u0e40\u0e1b\u0e48\u0e32\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 3000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7  \u0e0b\u0e2d\u0e22 5 (\u0e16\u0e19\u0e19\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 3) \u0e16\u0e19\u0e19\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 3 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0345569003018\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003018 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19-\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0123569002101\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002101 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 2569-07-03 3000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569001911\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001911 \u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 3000000 68103 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 110\/138-139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0525569001579\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e10\u0e01\u0e24\u0e0a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001579 \u0e1a\u0e08.\u0e28\u0e23\u0e10\u0e01\u0e24\u0e0a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 3000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 18  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e21\u0e48\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0655569002086\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002086 \u0e1a\u0e08.\u0e40\u0e04\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 3000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0955569000501\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e2b\u0e25\u0e07\u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000501 \u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e2b\u0e25\u0e07\u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 3000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 198-198\/1  \u0e16\u0e19\u0e19\u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569125310\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e27\u0e25 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125310 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0a\u0e27\u0e25 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 3000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 v09 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32 (\u0e2a\u0e35\u0e25\u0e219) \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125417\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e27\u0e48\u0e32 \u0e23\u0e35\u0e17\u0e23\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87100\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87100\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125417 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e27\u0e48\u0e32 \u0e23\u0e35\u0e17\u0e23\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 3000000 87100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u533b\u7642\u30fb\u798f\u7949 43  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b.47 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125425\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e2d\u0e2d\u0e25 \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e0b\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125425 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e2d\u0e2d\u0e25 \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e0b\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 3000000 69100 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 (legal compliance) \u0e17\u0e31\u0e49\u0e07\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 29\/30   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2204 \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 73 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125450\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e2a\u0e40\u0e0b\u0e35\u0e22 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125450 \u0e1a\u0e08.\u0e41\u0e04\u0e2a\u0e40\u0e0b\u0e35\u0e22 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 3000000 28299 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u88fd\u9020 33\/4  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30\u0e44\u0e19\u0e19\u0e4c\u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e27\u0e2d\u0e23\u0e4c (\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d) \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 34 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0505569014956\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014956 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 3000000 79110 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 249\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0585569000238\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e19\u0e31\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10307\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10307\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\",\"province_ja\":\"\u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\",\"search_text\":\"0585569000238 \u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e19\u0e31\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 3000000 10307 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e16\u0e31\u0e48\u0e27\u0e25\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u88fd\u9020 163  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569123767\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e35\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123767 \u0e1a\u0e08.\u0e25\u0e35\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 70209 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2823\/3  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e32\u0e22 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123775\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 \u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e32\u0e23\u0e4c\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123775 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e04 \u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e32\u0e23\u0e4c\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 999\/9   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b107-108 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 b1 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123945\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e01\u0e19\u0e01\u0e01\u0e34\u0e08\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123945 \u0e1a\u0e08.\u0e01\u0e23\u0e01\u0e19\u0e01\u0e01\u0e34\u0e08\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 47640 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e40\u0e01\u0e21 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 704\/1  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124151\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e2a\u0e15\u0e2d\u0e23\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e0b\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124151 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e2a\u0e15\u0e2d\u0e23\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e0b\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14 \u0e2a\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 843  \u0e16\u0e19\u0e19\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124461\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e48\u0e27\u0e15\u0e34\u0e49\u0e07 \u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124461 \u0e1a\u0e08.\u0e08\u0e34\u0e48\u0e27\u0e15\u0e34\u0e49\u0e07 \u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e42\u0e17\u0e23 \u0e41\u0e21\u0e04\u0e04\u0e32\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 56 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124631\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e1f \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124631 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e1f \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 46102 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e35 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 32 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569024441\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024441 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 87301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e1e\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 (home care) \u533b\u7642\u30fb\u798f\u7949 53\/1096  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034844\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e23\u0e38\u0e48\u0e07 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034844 \u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e23\u0e38\u0e48\u0e07 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0415569003416\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e25\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003416 \u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e25\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27\u0e1a\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e07\u0e01\u0e32\u0e41\u0e1f \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e41\u0e25\u0e30\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299\/205  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e01\u0e48\u0e40\u0e16\u0e37\u0e48\u0e2d\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0673569000511\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e27\u0e31\u0e12\u0e19\u0e4c (2541)\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0673569000511 \u0e2b\u0e08.\u0e18\u0e19\u0e27\u0e31\u0e12\u0e19\u0e4c (2541) 2569-07-01 3000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e22\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15  \u0e16\u0e19\u0e19\u0e2a\u0e31\u0e19\u0e04\u0e39\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0945569000650\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e21\u0e32\u0e19\u0e30\u0e2b\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":3000000,\"capital_display\":\"3,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000650 \u0e1a\u0e08.\u0e2d\u0e32\u0e21\u0e32\u0e19\u0e30\u0e2b\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 3000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e17\u0e31\u0e28\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e19\u0e33\u0e04\u0e13\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e27\u0e07\u0e1a\u0e38\u0e0d \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e1a\u0e31\u0e15\u0e23\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 7\/4  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e08\u0e34\u0e01 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569126235\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34 \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e42\u0e1f\u0e25\u0e27\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2990000,\"capital_display\":\"2,990,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126235 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34 \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e42\u0e1f\u0e25\u0e27\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2990000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e04 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131603\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e40\u0e17\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2700000,\"capital_display\":\"2,700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131603 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e40\u0e17\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2700000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e43\u0e14 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e0a\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u91d1\u878d\u30fb\u4fdd\u967a 46  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 97 (\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e0a\u0e04) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141382\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e25\u0e47\u0e15\u0e42\u0e01\u0e25\u0e27\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141382 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e25\u0e47\u0e15\u0e42\u0e01\u0e25\u0e27\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2500000 47723 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35\/34  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0313569001153\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e23\u0e20\u0e31\u0e17\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001153 \u0e2b\u0e08.\u0e27\u0e35\u0e23\u0e20\u0e31\u0e17\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-27 2500000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 240  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e14\u0e19\u0e40\u0e15\u0e35\u0e49\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0303569002834\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e08 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002834 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e08 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-22 2500000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 537\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0905569005902\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e32\u0e21\u0e2b\u0e22\u0e2d\u0e22 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005902 \u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e32\u0e21\u0e2b\u0e22\u0e2d\u0e22 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 2500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e33\u0e02\u0e19\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e19\u0e21\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/1  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569132961\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e21\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e23\u0e39\u0e40\u0e21\u0e19\u0e17\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132961 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e21\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e23\u0e39\u0e40\u0e21\u0e19\u0e17\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2500000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07  \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e17\u0e31\u0e28\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33 \u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 92\/8  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0415569003629\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e25\u0e0d\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003629 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e25\u0e0d\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2500000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e04\u0e32\u0e23\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27 \u0e15\u0e34\u0e14\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/242  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0463569000733\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e14\u0e34\u0e19\u0e17\u0e2d\u0e07\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000733 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e14\u0e34\u0e19\u0e17\u0e2d\u0e07 2569-07-11 2500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e14\u0e34\u0e19 \u0e2b\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u5efa\u8a2d 128  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e31\u0e22\u0e28\u0e23\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0655569002167\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 999 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002167 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 999 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 384  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0105569125069\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2500000,\"capital_display\":\"2,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125069 \u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 192,194   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 c11 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0575569004381\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e39\u0e08\u0e35 \u0e42\u0e1e\u0e23\u0e40\u0e0b\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2400000,\"capital_display\":\"2,400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004381 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e39\u0e08\u0e35 \u0e42\u0e1e\u0e23\u0e40\u0e0b\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2400000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e0a\u0e32\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0623569000740\",\"name_th\":\"\u0e2b\u0e08. \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e15\u0e47\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2200000,\"capital_display\":\"2,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000740 \u0e2b\u0e08. \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e15\u0e47\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 2569-07-22 2200000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 453  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e07\u0e1e\u0e34\u0e01\u0e38\u0e25 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0463569000768\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d.\u0e0b\u0e35.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2050000,\"capital_display\":\"2,050,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000768 \u0e2b\u0e08.\u0e40\u0e2d.\u0e0b\u0e35.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-21 2050000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 428  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e0b\u0e32\u0e25\u0e32\u0e40\u0e1b\u0e32 \u0e16\u0e19\u0e19\u0e16\u0e35\u0e19\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0105569142974\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e2d\u0e35 \u0e44\u0e17\u0e22-\u0e44\u0e0a\u0e19\u0e34\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142974 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e2d\u0e35 \u0e44\u0e17\u0e22-\u0e44\u0e0a\u0e19\u0e34\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 3  \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e41\u0e01\u0e07\u0e32\u0e21 14 \u0e41\u0e22\u0e01 4-5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143008\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e0b\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143008 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e0b\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e14\u0e39\u0e41\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1b\u0e32\u0e42\u0e0b\u0e48\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 26 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143075\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e01\u0e15\u0e48\u0e2d \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143075 \u0e1a\u0e08.\u0e1a\u0e2d\u0e01\u0e15\u0e48\u0e2d \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 85\/82  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 9 \u0e41\u0e22\u0e01 2-3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143164\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e19 \u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143164 \u0e1a\u0e08.\u0e14\u0e2d\u0e19 \u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 21\/54-55  \u0e2d\u0e32\u0e04\u0e32\u0e23c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143211\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e1a\u0e32\u0e23\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143211 \u0e1a\u0e08.\u0e42\u0e04\u0e1a\u0e32\u0e23\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e1b \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e42\u0e0b\u0e14\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 158\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e40\u0e19\u0e01\u0e27\u0e19\u0e34\u0e0a \u0e0a\u0e31\u0e49\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07 c \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 55 (\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143229\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e25\u0e31\u0e19 \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143229 \u0e1a\u0e08.\u0e2d\u0e35\u0e25\u0e31\u0e19 \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e09\u0e35\u0e14\u0e1f\u0e34\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e42\u0e1a\u0e17\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e2a\u0e01\u0e34\u0e19\u0e1a\u0e39\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 8  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 45 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143237\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143237 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1c\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/17  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e22\u0e39\u0e19\u0e34\u0e15 1 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143296\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143296 \u0e1a\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 796  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 43 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143326\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e25\u0e40\u0e14\u0e35\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47911\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47911\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143326 \u0e1a\u0e08.\u0e0a\u0e32\u0e25\u0e40\u0e14\u0e35\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 47911 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 105 \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 20 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143415\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e35 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143415 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e35 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 209  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 64 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143423\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e2d\u0e31\u0e25\u0e1f\u0e38\u0e15\u0e44\u0e17\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143423 \u0e1a\u0e08.\u0e0b\u0e32\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e2d\u0e31\u0e25\u0e1f\u0e38\u0e15\u0e44\u0e17\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 205  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 64 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025269\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025269 \u0e1a\u0e08.\u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e2a\u0e39\u0e15\u0e23 \u0e1c\u0e2a\u0e21 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 444\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569023525\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e44\u0e0b\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023525 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e44\u0e0b\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569039552\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e41\u0e04\u0e15\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039552 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e41\u0e04\u0e15\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e2a\u0e23\u0e30 \u0e15\u0e31\u0e14 \u0e14\u0e31\u0e14 \u0e2a\u0e23\u0e30\u0e44\u0e14\u0e23\u0e4c \u0e17\u0e33\u0e2a\u0e35\u0e1c\u0e21 \u0e17\u0e23\u0e35\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e28\u0e35\u0e23\u0e29\u0e30 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 11\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039579\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e0b\u0e32\u0e23\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039579 \u0e1a\u0e08.\u0e1a\u0e32\u0e0b\u0e32\u0e23\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 281\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039587\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 888 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039587 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 888 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32  \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19  \u0e08\u0e31\u0e14\u0e2b\u0e32  \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22  \u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32  \u0e1a\u0e49\u0e32\u0e19  \u0e04\u0e2d\u0e19\u0e42\u0e14  \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e2b\u0e21\u0e48  \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u4e0d\u52d5\u7523 88\/96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039617\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e2b\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039617 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e2b\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 77101 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e14\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 5\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569002195\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 \u0e42\u0e01\u0e23\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10419\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10419\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002195 \u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 \u0e42\u0e01\u0e23\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 10419 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e01\u0e24\u0e29\u0e13\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e01\u0e24\u0e29\u0e13\u0e32 \u88fd\u9020 87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007811\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e25\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007811 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e35\u0e25\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d  \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e1b\u0e23\u0e31\u0e07\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14  \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e0d\u52d5\u7523 461  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001161\",\"name_th\":\"\u0e2b\u0e08.126 \u0e04\u0e25\u0e35\u0e19\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001161 \u0e2b\u0e08.126 \u0e04\u0e25\u0e35\u0e19 2569-07-31 2000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e01\u0e48\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 17\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0503569005335\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e15\u0e23\u0e1b\u0e34\u0e0e\u0e01 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005335 \u0e2b\u0e08.\u0e44\u0e15\u0e23\u0e1b\u0e34\u0e0e\u0e01 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-31 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 28\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016941\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e19\u0e1b\u0e31\u0e19 \u0e40\u0e01\u0e23\u0e17\u0e25\u0e35\u0e48 \u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016941 \u0e1a\u0e08.\u0e1b\u0e31\u0e19\u0e1b\u0e31\u0e19 \u0e40\u0e01\u0e23\u0e17\u0e25\u0e35\u0e48 \u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u6559\u80b2 63\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016959\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e34\u0e08\u0e1a\u0e35\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016959 \u0e1a\u0e08.\u0e1e\u0e31\u0e12\u0e19\u0e01\u0e34\u0e08\u0e1a\u0e35\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 76  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016967\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e14\u0e35\u0e49 \u0e41\u0e1e\u0e17\u0e17\u0e34\u0e2a\u0e31\u0e19 \u0e40\u0e04\u0e32\u0e40\u0e0b\u0e34\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e35\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016967 \u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e14\u0e35\u0e49 \u0e41\u0e1e\u0e17\u0e17\u0e34\u0e2a\u0e31\u0e19 \u0e40\u0e04\u0e32\u0e40\u0e0b\u0e34\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e35\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e34\u0e15 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e14\u0e35 (well - being) \u533b\u7642\u30fb\u798f\u7949 199\/528  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004900\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e0a\u0e19\u0e30 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004900 \u0e1a\u0e08.\u0e1e\u0e32\u0e0a\u0e19\u0e30 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 2000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01 \u0e04\u0e39 \u0e04\u0e25\u0e2d\u0e07 \u0e2a\u0e23\u0e30\u0e19\u0e49\u0e33 \u0e2b\u0e19\u0e2d\u0e07 \u0e1a\u0e36\u0e07 \u0e25\u0e33\u0e19\u0e49\u0e33 \u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19  \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e04\u0e31\u0e19\u0e01\u0e31\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e32\u0e07 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 202  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e48\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0843569001485\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e22 \u0e1e\u0e39\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001485 \u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e22 \u0e1e\u0e39\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-31 2000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5efa\u8a2d 14\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569142567\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e42\u0e2d\u0e1a\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142567 \u0e1a\u0e08.\u0e0b\u0e35\u0e42\u0e2d\u0e1a\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 14\/48   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 301 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 69 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142575\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142575 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 35102 .\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging system) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e15\u0e39\u0e49\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e15\u0e39\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e15\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e40\u0e2a\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07 \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e25\u0e07\u0e17\u0e38\u0e19\u0e23\u0e48\u0e27\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 2034\/36  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142699\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e14\u0e35\u0e0b\u0e35 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e15\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142699 \u0e1a\u0e08.\u0e40\u0e2d\u0e14\u0e35\u0e0b\u0e35 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e15\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e21\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e2d\u0e21\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e4c 4 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028403\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028403 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e21\u0e49\u0e27\u0e19\u0e23\u0e35\u0e14\u0e23\u0e49\u0e2d\u0e19 \u0e23\u0e35\u0e14\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/178  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023436\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e1a\u0e34 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023436 \u0e1a\u0e08.\u0e42\u0e01\u0e1a\u0e34 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 96309 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 111\/260  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0203569003335\",\"name_th\":\"\u0e2b\u0e08.\u0e2e\u0e48\u0e32\u0e27\u0e40\u0e27\u0e48\u0e22 \u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003335 \u0e2b\u0e08.\u0e2e\u0e48\u0e32\u0e27\u0e40\u0e27\u0e48\u0e22 \u0e1f\u0e39\u0e49\u0e14 2569-07-30 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e38\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 (delivery) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/210  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039536\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039536 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e02\u0e27\u0e14 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 33\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0505569016886\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016886 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e15\u0e30\u0e40\u0e01\u0e35\u0e22\u0e1a\u0e44\u0e21\u0e49 \u0e0a\u0e49\u0e2d\u0e19 \u0e2a\u0e49\u0e2d\u0e21 \u0e21\u0e35\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e1a\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e15\u0e48\u0e32\u0e07 \u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 260\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0815569002271\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e2a \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e44\u0e25\u0e19\u0e34\u0e07 \u0e42\u0e1a\u0e17\u0e32\u0e19\u0e34\u0e04\u0e2d\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20293\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20293\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002271 \u0e1a\u0e08.\u0e44\u0e2e\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e2a \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e44\u0e25\u0e19\u0e34\u0e07 \u0e42\u0e1a\u0e17\u0e32\u0e19\u0e34\u0e04\u0e2d\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 2000000 20293 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22\u0e01\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e15\u0e31\u0e27\u0e1e\u0e32\u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19\u0e34\u0e04\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e1a\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u88fd\u9020 43\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0105569142486\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e19\u0e14\u0e35\u0e49.\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142486 \u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e19\u0e14\u0e35\u0e49.\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 586\/175  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142516\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39 \u0e44\u0e17\u0e1b\u0e4c\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142516 \u0e1a\u0e08.\u0e17\u0e39 \u0e44\u0e17\u0e1b\u0e4c\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32  \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 140  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e2d\u0e31\u0e21\u0e1e\u0e27\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025056\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e21\u0e42\u0e1a\u0e23 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025056 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e21\u0e42\u0e1a\u0e23 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 2000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 928  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569039421\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039421 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 2000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 77\/75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039455\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e40\u0e17\u0e04 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039455 \u0e1a\u0e08.\u0e1a\u0e35 \u0e40\u0e17\u0e04 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 413\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039463\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e25\u0e34\u0e2a \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039463 \u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e25\u0e34\u0e2a \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 2000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e44\u0e2d\u0e17\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 517\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039471\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e35\u0e22\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e01\u0e14\u0e40\u0e08\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039471 \u0e1a\u0e08.\u0e40\u0e23\u0e35\u0e22\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e01\u0e14\u0e40\u0e08\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 2000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e25\u0e33\u0e42\u0e1e\u0e07  \u0e2b\u0e39\u0e1f\u0e31\u0e07 \u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e21\u0e32\u0e2a\u0e4c \u0e04\u0e35\u0e22\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14  \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 517\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0115569025005\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025005 \u0e1a\u0e08.\u0e27\u0e35 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 2000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e31\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e2d\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e1c\u0e48\u0e19\u0e1e\u0e31\u0e1a \u0e42\u0e1a\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e09\u0e25\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 561\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025013\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e23\u0e23\u0e48\u0e32 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24204\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24204\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025013 \u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e23\u0e23\u0e48\u0e32 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 2000000 24204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 885\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569039404\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e2d\u0e07\u0e14\u0e35\u0e21\u0e35\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79909\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79909\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039404 \u0e1a\u0e08.\u0e08\u0e2d\u0e07\u0e14\u0e35\u0e21\u0e35\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 2000000 79909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 327\/247  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007749\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e25\u0e21\u0e01\u0e23\u0e38\u0e4a\u0e1b 1978 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007749 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e25\u0e21\u0e01\u0e23\u0e38\u0e4a\u0e1b 1978 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e17\u0e32\u0e2b\u0e19\u0e49\u0e32 \u0e17\u0e32\u0e15\u0e31\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/26  \u0e16\u0e19\u0e19\u0e1b\u0e32\u0e01\u0e0a\u0e48\u0e2d\u0e07-\u0e0b\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e48\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0775569003189\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003189 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e22\u0e32\u0e21 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 113\/32  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0845569010940\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e19\u0e31\u0e2a\u0e19\u0e31\u0e19\u0e17\u0e4c 888 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"88901\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"88901\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010940 \u0e1a\u0e08.\u0e21\u0e19\u0e31\u0e2a\u0e19\u0e31\u0e19\u0e17\u0e4c 888 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 2000000 88901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e14\u0e47\u0e01\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u533b\u7642\u30fb\u798f\u7949 97\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010958\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49 \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010958 \u0e1a\u0e08.\u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49 \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 2000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e2d\u0e1a\u0e1c\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 3\/83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0103569008117\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19\u0e01\u0e32\u0e15\u0e49\u0e21\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008117 \u0e2b\u0e08.\u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19\u0e01\u0e32\u0e15\u0e49\u0e21 2569-07-27 2000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 128  \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141579\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e2d\u0e35\u0e40\u0e2d\u0e2a\u0e08\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e19\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141579 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e2d\u0e35\u0e40\u0e2d\u0e2a\u0e08\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e19\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e25\u0e21\u0e41\u0e2b\u0e49\u0e07 \u0e15\u0e31\u0e27\u0e01\u0e23\u0e2d\u0e07\u0e25\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141625\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e27\u0e14\u0e32 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141625 \u0e1a\u0e08.\u0e44\u0e2e\u0e27\u0e14\u0e32 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e02\u0e2d\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e48\u0e07  (internet of things : iot \u60c5\u5831\u901a\u4fe1\u30fbit 55  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 30 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141731\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35 \u0e42\u0e04 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141731 \u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35 \u0e42\u0e04 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e48\u0e21 \u5efa\u8a2d 82\/178  \u0e0b\u0e2d\u0e22 \u0e0b\u0e34\u0e40\u0e21\u0e19\u0e15\u0e4c\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141927\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e42\u0e2e\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01461\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01461\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141927 \u0e1a\u0e08.\u0e2d\u0e32\u0e42\u0e2e\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 01461 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e41\u0e21\u0e48\u0e44\u0e02\u0e48 \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e44\u0e02\u0e48\u0e2a\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 467  \u0e0b\u0e2d\u0e22 \u0e41\u0e01\u0e49\u0e27\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141943\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e25\u0e35\u0e48 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141943 \u0e1a\u0e08.\u0e08\u0e39\u0e25\u0e35\u0e48 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 599  \u0e2d\u0e32\u0e04\u0e32\u0e23tur gub chan  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 tc04 \u0e16\u0e19\u0e19\u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e0a\u0e48\u0e2d\u0e07\u0e19\u0e19\u0e17\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142010\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0b \u0e42\u0e08\u0e25\u0e38\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142010 \u0e1a\u0e08.\u0e40\u0e2d\u0e0b \u0e42\u0e08\u0e25\u0e38\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 264-266  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142061\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142061 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 marketplace \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 220\/29  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e19\u0e38\u0e01\u0e39\u0e25 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142095\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142095 \u0e1a\u0e08.\u0e42\u0e2d\u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2823\/3  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142125\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e44\u0e17\u0e48 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142125 \u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e44\u0e17\u0e48 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 1152  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e484 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142192\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142192 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 123  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e35.\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3501-3504 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028268\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e19 \u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028268 \u0e1a\u0e08.\u0e21\u0e39\u0e19 \u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 165\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023339\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e21\u0e31\u0e01\u0e08\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023339 \u0e1a\u0e08.\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e21\u0e31\u0e01\u0e08\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 67\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569039153\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e2d\u0e30\u0e40\u0e15\u0e25\u0e34\u0e40\u0e22\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039153 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e2d\u0e30\u0e40\u0e15\u0e25\u0e34\u0e40\u0e22\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 488\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039188\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039188 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 105\/82  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569004091\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e19\u0e32\u0e23\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20131\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20131\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004091 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e19\u0e32\u0e23\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 20131 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48 \u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 333  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0403569003333\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35  \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003333 \u0e2b\u0e08.\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35  \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 2569-07-27 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 199\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001693\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001693 \u0e1a\u0e08.\u0e42\u0e0b\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001707\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e34\u0e07 \u0e40\u0e08\u0e35\u0e22 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001707 \u0e1a\u0e08.\u0e15\u0e34\u0e07 \u0e40\u0e08\u0e35\u0e22 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000981\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e0b\u0e31\u0e1a\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000981 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e0b\u0e31\u0e1a\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32-\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e02\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e14\u0e49\u0e27\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 170  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0485569000999\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e2d\u0e41\u0e0b\u0e23\u0e4c\u0e1f \u0e1b\u0e32\u0e23\u0e35\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000999 \u0e1a\u0e08.\u0e40\u0e25\u0e2d\u0e41\u0e0b\u0e23\u0e4c\u0e1f \u0e1b\u0e32\u0e23\u0e35\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e2b\u0e34\u0e19\u0e2a\u0e35 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0505569016801\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016801 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 288\/31-32  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0663569000618\",\"name_th\":\"\u0e2b\u0e08.\u0e1b.\u0e1b\u0e25\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e0b\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0663569000618 \u0e2b\u0e08.\u0e1b.\u0e1b\u0e25\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e0b\u0e4c 2569-07-27 2000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0705569003421\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10301\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10301\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003421 \u0e1a\u0e08.\u0e44\u0e17\u0e22-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 10301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 27\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0835569013825\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19 \u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e08 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013825 \u0e1a\u0e08.\u0e40\u0e0b\u0e19 \u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e08 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 96101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 7\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010915\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010915 \u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e33 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e21\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 13\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0965569000587\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35  \u0e44\u0e1b\u0e1b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0965569000587 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35  \u0e44\u0e1b\u0e1b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 222\/9  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e22\u0e1e\u0e32\u0e2a \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569141161\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e04\u0e32\u0e23\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46492\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46492\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141161 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e04\u0e32\u0e23\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 2000000 46492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 410\/85  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e34\u0e40\u0e2d\u0e47\u0e01\u0e40\u0e0b\u0e47\u0e04\u0e04\u0e34\u0e27\u0e17\u0e35\u0e1f \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024793\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e39\u0e2d\u0e34\u0e17 \u0e40\u0e0a\u0e25\u0e27\u0e34\u0e48\u0e07 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024793 \u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e39\u0e2d\u0e34\u0e17 \u0e40\u0e0a\u0e25\u0e27\u0e34\u0e48\u0e07 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 2000000 25119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e25\u0e2b\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 46\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 23 \u0e0b\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e44\u0e17\u0e22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569039030\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039030 \u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 2000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 400\/726   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1.4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0505569016720\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e23\u0e34\u0e0a \u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10619\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10619\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016720 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e23\u0e34\u0e0a \u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 2000000 10619 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0775569003146\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e0b\u0e35 \u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003146 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e0b\u0e35 \u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 2000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5efa\u8a2d 161\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0845569010893\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e21\u0e1b\u0e4c\u0e04\u0e48\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010893 \u0e1a\u0e08.\u0e41\u0e2e\u0e21\u0e1b\u0e4c\u0e04\u0e48\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 38\/115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569139621\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e0b\u0e35\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139621 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e0b\u0e35\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 62023 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 124  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 67 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139728\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139728 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 32\/49  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 73 (\u0e1e\u0e23\u0e01\u0e38\u0e25\u0e27\u0e31\u0e12\u0e19\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139752\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e04\u0e27\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e17 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81292\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81292\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139752 \u0e1a\u0e08.\u0e2d\u0e30\u0e04\u0e27\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e17 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 81292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e43\u0e19 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e14\u0e35 \u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 302\/88  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e19\u0e0b\u0e35\u0e42\u0e2d \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139850\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e1f\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139850 \u0e1a\u0e08.\u0e42\u0e0b\u0e1f\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139990\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2a\u0e2d\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139990 \u0e1a\u0e08.\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2a\u0e2d\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b (\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19) \u533b\u7642\u30fb\u798f\u7949 995\/12  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140041\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2a\u0e15\u0e4c\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140041 \u0e1a\u0e08.\u0e40\u0e17\u0e2a\u0e15\u0e4c\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 222\/118  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e2e\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 18 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140076\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e27\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140076 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e27\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 192,194   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 c13 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140220\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e22\u0e39\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140220 \u0e1a\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e22\u0e39\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e41\u0e1c\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c (pcb) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e41\u0e1c\u0e48\u0e19\u0e25\u0e32\u0e21\u0e34\u0e40\u0e19\u0e15\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 (ccl) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1840  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e2e\u0e34\u0e25\u0e2a\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 821 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 8-9 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140254\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140254 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 server \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c111  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1924-1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140343\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140343 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e44\u0e1f\u0e41\u0e2d\u0e25\u0e2d\u0e35\u0e14\u0e35 \u0e1b\u0e49\u0e32\u0e22\u0e44\u0e27\u0e19\u0e34\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 70\/96  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 30 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140424\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e27\u0e34\u0e25\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140424 \u0e1a\u0e08.\u0e0b\u0e35\u0e27\u0e34\u0e25\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 96  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140432\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e0b\u0e19\u0e34\u0e04 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140432 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e0b\u0e19\u0e34\u0e04 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 140  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e2d\u0e31\u0e21\u0e1e\u0e27\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140467\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e27\u0e22\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140467 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e27\u0e22\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82  \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140629\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 3 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140629 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 3 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 32120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e21\u0e38\u0e01 \u0e2b\u0e22\u0e01 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u88fd\u9020 1023  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e2a \u0e2a\u0e22\u0e32\u0e21 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 159 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 15 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140700\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e19\u0e2e\u0e27\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140700 \u0e1a\u0e08.\u0e14\u0e31\u0e19\u0e2e\u0e27\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e27\u0e35\u0e40\u0e08 (vj) \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (presenter) \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14 (live streaming) \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 604\/3  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140726\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e08\u0e2d\u0e07 \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140726 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e08\u0e2d\u0e07 \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 6  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 12 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140742\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e29\u0e4c\u0e09\u0e39\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140742 \u0e1a\u0e08.\u0e2b\u0e07\u0e29\u0e4c\u0e09\u0e39\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07-\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c(\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/176  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e2d\u0e23\u0e4c\u0e04\u0e34\u0e14\u0e1b\u0e32\u0e23\u0e4c\u0e04 2 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140751\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e19\u0e40\u0e1a\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140751 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e19\u0e40\u0e1a\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 62022 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e40\u0e40\u0e27\u0e23\u0e4c\u0e40\u0e40\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e40\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e3523 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1723(\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140939\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e21\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47594\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47594\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140939 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e21\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47594 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e19\u0e15\u0e23\u0e35\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 140  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e2d\u0e31\u0e21\u0e1e\u0e27\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024599\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1c\u0e48 \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93299\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93299\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024599 \u0e1a\u0e08.\u0e44\u0e1c\u0e48 \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 93299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e47\u0e17\u0e2a\u0e01\u0e35 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e08\u0e47\u0e17\u0e2a\u0e01\u0e35 \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 35\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024637\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024637 \u0e1a\u0e08.\u0e1a\u0e34\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/122   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 104 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024645\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e09\u0e27\u0e19 \u0e2d\u0e35\u0e4b\u0e1b\u0e34\u0e19 \u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e19\u0e19\u0e34\u0e07 \u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024645 \u0e1a\u0e08.\u0e40\u0e2a\u0e09\u0e27\u0e19 \u0e2d\u0e35\u0e4b\u0e1b\u0e34\u0e19 \u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e19\u0e19\u0e34\u0e07 \u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u0e1a\u0e32\u0e23\u0e4c\u0e1a\u0e35\u0e04\u0e34\u0e27 \u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e0a\u0e32\u0e1a\u0e39 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e22\u0e48\u0e32\u0e07 \u0e15\u0e49\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19 \u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 16\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027873\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e14 \u0e2e\u0e2d\u0e25\u0e25\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027873 \u0e1a\u0e08.\u0e41\u0e0b\u0e14 \u0e2e\u0e2d\u0e25\u0e25\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 333\/931  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e34\u0e04 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 26 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027911\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e19-\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e35\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027911 \u0e1a\u0e08.\u0e2d\u0e2d\u0e19-\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e35\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e25\u0e30\u0e04\u0e23 \u0e0b\u0e35\u0e23\u0e35\u0e48\u0e2a\u0e4c \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e31\u0e49\u0e19 \u0e40\u0e01\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 33  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 25 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027938\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a \u0e14\u0e31\u0e21\u0e23\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027938 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a \u0e14\u0e31\u0e21\u0e23\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46900 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/240  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e25\u0e34\u0e25\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e30\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038831\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038831 \u0e1a\u0e08.\u0e23\u0e34\u0e0a \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 ( \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 ) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 45\/71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038882\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e01\u0e34\u0e49\u0e25 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038882 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e01\u0e34\u0e49\u0e25 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 189\/74-75  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009874\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e07\u0e44\u0e17\u0e48 \u0e2b\u0e25\u0e07\u0e40\u0e09\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009874 \u0e1a\u0e08.\u0e2b\u0e25\u0e07\u0e44\u0e17\u0e48 \u0e2b\u0e25\u0e07\u0e40\u0e09\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 64\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569004023\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e2d\u0e35\u0e2a\u0e17\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004023 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e2d\u0e35\u0e2a\u0e17\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e01\u0e23\u0e23\u0e21 \u4e0d\u52d5\u7523 147\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0343569002001\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569002001 \u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-24 2000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001730\",\"name_th\":\"\u0e2b\u0e08.\u0e0a.\u0e28\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001730 \u0e2b\u0e08.\u0e0a.\u0e28\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-24 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 116  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003998\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e27\u0e32 \u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46205\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46205\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003998 \u0e1a\u0e08.\u0e19\u0e32\u0e27\u0e32 \u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46205 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0455569001553\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001553 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e22\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c (\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e01\u0e23\u0e07 \u0e04\u0e2d\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e0a\u0e32\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e30\u0e1a\u0e30\u0e17\u0e23\u0e32\u0e22 \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e32\u0e22\u0e08\u0e39\u0e07 \u0e1b\u0e25\u0e2d\u0e01\u0e04\u0e2d \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001561\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001561 \u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e01\u0e25\u0e34\u0e48\u0e19\u0e01\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e34\u0e21\u0e1d\u0e35\u0e1b\u0e32\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e25\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0475569001677\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e0a\u0e34\u0e23\u0e39\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001677 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e0a\u0e34\u0e23\u0e39\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0495569000590\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32 \u0e42\u0e23\u0e42\u0e1a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e22\u0e39\u0e40\u0e2d\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000590 \u0e1a\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32 \u0e42\u0e23\u0e42\u0e1a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e22\u0e39\u0e40\u0e2d\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e44\u0e23\u0e49\u0e04\u0e19\u0e02\u0e31\u0e1a (uav) \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e20\u0e32\u0e04\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19\u0e44\u0e23\u0e49\u0e04\u0e19\u0e02\u0e31\u0e1a (ugv) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e44\u0e23\u0e49\u0e04\u0e19\u0e02\u0e31\u0e1a (anti uav) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 910  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016622\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e27\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016622 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e27\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016665\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016665 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e19\u0e27\u0e14 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 22\/2  \u0e0b\u0e2d\u0e22 13(\u0e16\u0e19\u0e19\u0e19\u0e34\u0e21\u0e21\u0e32\u0e19\u0e40\u0e2b\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c) \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016681\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016681 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0705569003383\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e42\u0e04\u0e48 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003383 \u0e1a\u0e08.\u0e42\u0e04\u0e42\u0e04\u0e48 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 276  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007524\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e01\u0e34\u0e08\u0e42\u0e01\u0e28\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47713\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47713\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007524 \u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e01\u0e34\u0e08\u0e42\u0e01\u0e28\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 47713 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15-\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e0a\u0e4a\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e43\u0e2a\u0e48\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e1c\u0e49\u0e32 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e1e\u0e35\u0e27\u0e35\u0e0b\u0e35 \u0e2b\u0e19\u0e31\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007958\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e04\u0e40\u0e23\u0e14 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007958 \u0e1a\u0e08.\u0e41\u0e1e\u0e04\u0e40\u0e23\u0e14 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 48\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0813569000489\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e0b\u0e34\u0e27\u0e34\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0813569000489 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e0b\u0e34\u0e27\u0e34\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e2a\u0e4c 2569-07-24 2000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e16\u0e21\u0e14\u0e34\u0e19 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e40\u0e08\u0e32\u0e30\u0e2b\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 579  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569013663\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e2d\u0e21\u0e1f\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013663 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e2d\u0e21\u0e1f\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\\\"\\\" \u4e0d\u52d5\u7523 199\/113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013728\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1a\u0e35 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013728 \u0e1a\u0e08.\u0e17\u0e35\u0e1a\u0e35 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 77109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 13\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010818\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e2a\u0e23\u0e34\u0e22\u0e30 \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010818 \u0e1a\u0e08.\u0e2d\u0e34\u0e2a\u0e23\u0e34\u0e22\u0e30 \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 148\/97  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010826\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e2a\u0e21\u0e38\u0e22 \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010826 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e2a\u0e21\u0e38\u0e22 \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u5efa\u8a2d 16\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010834\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e25\u0e2a\u0e4c \u0e01\u0e2d\u0e15\u0e15\u0e49\u0e32 \u0e2d\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010834 \u0e1a\u0e08.\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e25\u0e2a\u0e4c \u0e01\u0e2d\u0e15\u0e15\u0e49\u0e32 \u0e2d\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e1a\u0e32\u0e23\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 59\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010851\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e14\u0e2a\u0e40\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010851 \u0e1a\u0e08.\u0e42\u0e14\u0e2a\u0e40\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 122\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010877\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23 \u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010877 \u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23 \u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569138594\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138594 \u0e1a\u0e08.\u0e18\u0e19\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e42\u0e2d\u0e19 \u0e08\u0e33\u0e19\u0e33 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e0a\u0e48\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 361  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e2b\u0e21\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138632\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138632 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 36\/156  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 rk biz center \u0e16\u0e19\u0e19\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138721\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04\u0e17\u0e35 \u0e44\u0e25\u0e1f\u0e4c\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138721 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04\u0e17\u0e35 \u0e44\u0e25\u0e1f\u0e4c\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e34\u0e28\u0e32\u0e0a\u0e25 \u0e14\u0e23\u0e35\u0e21\u0e27\u0e31\u0e25\u0e40\u0e25\u0e48\u0e22\u0e4c \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e23\u0e30\u0e21\u0e32\u0e14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138764\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e14\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138764 \u0e1a\u0e08.\u0e2d\u0e30\u0e14\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e07\u0e34\u0e19 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e44\u0e02\u0e48\u0e21\u0e38\u0e01 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e41\u0e1e\u0e25\u0e15\u0e17\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 92\/47  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138802\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e42\u0e23\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138802 \u0e1a\u0e08.\u0e21\u0e34\u0e42\u0e23\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 (\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07) \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/35  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138811\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e19\u0e14\u0e34\u0e40\u0e14\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138811 \u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e19\u0e14\u0e34\u0e40\u0e14\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1818  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e2a\u0e32 \u0e17\u0e39  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1816 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138977\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e42\u0e25\u0e23\u0e32 \u0e41\u0e04\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138977 \u0e1a\u0e08.\u0e40\u0e27\u0e42\u0e25\u0e23\u0e32 \u0e41\u0e04\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 725  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e42\u0e17\u0e23  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 157 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138985\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e41\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138985 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e41\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 725  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e42\u0e17\u0e23  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 130 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139001\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e07\u0e23\u0e31\u0e0d\u0e08\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139001 \u0e1a\u0e08.\u0e1f\u0e2d\u0e07\u0e23\u0e31\u0e0d\u0e08\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 33  \u0e0b\u0e2d\u0e22 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c 3 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139019\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e1f\u0e39\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139019 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e1f\u0e39\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e1a\u0e23\u0e01 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 72  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139108\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e23\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139108 \u0e1a\u0e08.\u0e27\u0e23\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 9\/86  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 144 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139370\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e2a\u0e15\u0e31\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139370 \u0e1a\u0e08.\u0e1a\u0e2d\u0e2a\u0e15\u0e31\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e4d\u0e32\u0e27\u0e31\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e4d\u0e32\u0e2d\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/35  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139396\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139396 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19  \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e0d\u52d5\u7523 8  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e27\u0e31\u0e19 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1740 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139515\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e23\u0e13\u0e20\u0e39\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46499\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46499\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139515 \u0e1a\u0e08.\u0e1e\u0e23\u0e23\u0e13\u0e20\u0e39\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 46499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6\/5  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 35\/1 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139591\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e35\u0e1f \u0e0a\u0e31\u0e01\u0e15\u0e34 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139591 \u0e1a\u0e08.\u0e0a\u0e35\u0e1f \u0e0a\u0e31\u0e01\u0e15\u0e34 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71  \u0e16\u0e19\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e32\u0e23\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024483\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e0a\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024483 \u0e1a\u0e08.\u0e20\u0e39\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e0a\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 999  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027814\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e2a\u0e4c \u0e40\u0e04\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027814 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e2a\u0e4c \u0e40\u0e04\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 82110 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 75\/111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022740\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e04\u0e27\u0e07 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022740 \u0e1a\u0e08.\u0e41\u0e21\u0e04\u0e27\u0e07 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e2e\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e02\u0e19\u0e21 \u88fd\u9020 24\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022791\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c 468 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022791 \u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c 468 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 31\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569038645\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038645 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e25\u0e2d\u0e19 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e1a\u0e32\u0e19\u0e1e\u0e31\u0e1a \u0e21\u0e37\u0e2d\u0e08\u0e31\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e23\u0e30\u0e41\u0e08 \u0e04\u0e35\u0e21 \u0e44\u0e02\u0e04\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e27\u0e48\u0e32\u0e19 \u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e0a\u0e48\u0e19\u0e01\u0e4a\u0e2d\u0e01\u0e19\u0e49\u0e33 \u0e1d\u0e31\u0e01\u0e1a\u0e31\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e49\u0e2d\u0e15\u0e48\u0e2d\u0e17\u0e48\u0e2d \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u0e2a\u0e27\u0e34\u0e15\u0e0a\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e31\u0e4a\u0e01\u0e44\u0e1f \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e15\u0e30\u0e1b\u0e39 \u0e25\u0e27\u0e14\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 889\/340  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038670\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e14\u0e22\u0e4c \u0e2e\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038670 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e14\u0e22\u0e4c \u0e2e\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 337\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038726\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e27\u0e19\u0e17\u0e23\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038726 \u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e27\u0e19\u0e17\u0e23\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07  \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 89\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038742\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e19\u0e32\u0e27\u0e35\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038742 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e19\u0e32\u0e27\u0e35\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 234\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038807\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e04 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038807 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e04 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30 \u0e08\u0e31\u0e14\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569002128\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e41\u0e1e\u0e47\u0e1a \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17020\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17020\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002128 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e41\u0e1e\u0e47\u0e1a \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 17020 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e16\u0e38\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e34\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e23\u0e31\u0e01\u0e29\u0e4c\u0e42\u0e25\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 218  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0345569003352\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e31\u0e25\u0e25\u0e20 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003352 \u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e31\u0e25\u0e25\u0e20 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 226\/26  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2a\u0e32\u0e27\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e0a\u0e22\u0e32\u0e07\u0e01\u0e39\u0e39\u0e23 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0405569007136\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e1a\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007136 \u0e1a\u0e08.\u0e19\u0e32\u0e1a\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0443569000873\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 168\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000873 \u0e2b\u0e08.\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 168 2569-07-23 2000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 36\/1  \u0e0b\u0e2d\u0e22 \u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c 49 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0475569001669\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1a\u0e35\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001669 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1a\u0e35\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 241\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016606\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e40\u0e14\u0e49\u0e19\u0e04\u0e32\u0e0b\u0e48\u0e32\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016606 \u0e1a\u0e08.\u0e42\u0e01\u0e40\u0e14\u0e49\u0e19\u0e04\u0e32\u0e0b\u0e48\u0e32\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7\/8  \u0e16\u0e19\u0e19\u0e21\u0e39\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0705569003324\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e27\u0e31\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003324 \u0e1a\u0e08.\u0e2b\u0e27\u0e31\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e42\u0e23\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0745569007893\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e07\u0e44\u0e17\u0e48 \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007893 \u0e1a\u0e08.\u0e08\u0e07\u0e44\u0e17\u0e48 \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 46694 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e16\u0e38\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c \u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c \u0e40\u0e17\u0e1b \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e22\u0e37\u0e14 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e1b\u0e23\u0e34\u0e49\u0e19 \u0e0b\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 117\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0775569003090\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22-\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003090 \u0e1a\u0e08.\u0e44\u0e17\u0e22-\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 39\/1345  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e31\u0e27\u0e19\u0e32 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0845569010796\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e22\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01 663 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010796 \u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e22\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01 663 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e42\u0e23\u0e07\u0e22\u0e34\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e19\u0e27\u0e14 \u0e2a\u0e1b\u0e32 \u5bbf\u6cca\u30fb\u98f2\u98df 168\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569006101\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e19\u0e39\u0e0b \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006101 \u0e1a\u0e08.\u0e2a\u0e19\u0e39\u0e0b \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 145\/33  \u0e16\u0e19\u0e19\u0e41\u0e2a\u0e07\u0e28\u0e23\u0e35 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569137717\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e1a\u0e35 \u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137717 \u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e1a\u0e35 \u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01  \u0e15\u0e36\u0e01 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e21\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07  \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 138  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e48\u0e2d\u0e21\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e07\u0e48\u0e32\u0e07\u0e32\u0e21 \u0e2a\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137865\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e39\u0e40\u0e04 \u0e42\u0e2e\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137865 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e39\u0e40\u0e04 \u0e42\u0e2e\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14   \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u5efa\u8a2d 164  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e04 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137962\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e34\u0e2a \u0e40\u0e17\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137962 \u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e34\u0e2a \u0e40\u0e17\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e27\u0e17\u0e4c\u0e2d\u0e34\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 399  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e19\u0e08 21  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2207-2208 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 22 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137971\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e32\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137971 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e32\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e21\u0e19\u0e39 \u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1\/37  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c 3 \u0e41\u0e22\u0e01 8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138098\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e23\u0e4c\u0e2a \u0e04\u0e31\u0e21 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e19 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c(\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138098 \u0e1a\u0e08.\u0e0b\u0e2d\u0e23\u0e4c\u0e2a \u0e04\u0e31\u0e21 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e19 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c(\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 46530 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 718\/28  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2d\u0e40\u0e27\u0e19\u0e34\u0e27 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e0b\u0e32\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138152\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e21\u0e39\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138152 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e21\u0e39\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 28   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a2\/1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e17\u0e27\u0e34\u0e17 101\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138373\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e22\u0e4c \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e19\u0e34\u0e27\u0e17\u0e23\u0e34\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138373 \u0e1a\u0e08.\u0e40\u0e04\u0e22\u0e4c \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e19\u0e34\u0e27\u0e17\u0e23\u0e34\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38  \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49  \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 170\/72  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 16 (\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138411\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e27\u0e19\u0e17\u0e32\u0e23\u0e48\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138411 \u0e1a\u0e08.\u0e41\u0e27\u0e19\u0e17\u0e32\u0e23\u0e48\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 46900 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 158  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138446\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e23\u0e48\u0e32 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138446 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e23\u0e48\u0e32 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32  \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 395\/589  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138471\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e25 \u0e01\u0e27\u0e32\u0e07\u0e15\u0e38\u0e49\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138471 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e25 \u0e01\u0e27\u0e32\u0e07\u0e15\u0e38\u0e49\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07 (\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23) \u904b\u8f38\u30fb\u7269\u6d41 554   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3s12 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2d\u0e42\u0e28\u0e01-\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024220\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e1b\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024220 \u0e1a\u0e08.\u0e08\u0e39\u0e1b\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e42\u0e21\u0e1a\u0e32\u0e22\u0e41\u0e2d\u0e1e \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c (hardware and software) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 (network system) \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (electronic systems) \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u60c5\u5831\u901a\u4fe1\u30fbit 788\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569022707\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e15\u0e4b\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022707 \u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e15\u0e4b\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e42\u0e1f\u0e21 \u0e40\u0e17\u0e1b\u0e01\u0e32\u0e27 \u0e40\u0e17\u0e1b\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0165569001670\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04 \u0e44\u0e17\u0e22 \u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001670 \u0e1a\u0e08.\u0e42\u0e04 \u0e44\u0e17\u0e22 \u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e35\u0e2c\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 60\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038327\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 407 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038327 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 407 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 453\/270  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038335\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038335 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 82199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 77\/188  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038360\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e20\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 8999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038360 \u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e20\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 8999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 25\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038386\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038386 \u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e2a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e25\u0e33\u0e42\u0e1e\u0e07 \u0e2b\u0e39\u0e1f\u0e31\u0e07 \u0e2a\u0e32\u0e22\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e40\u0e21\u0e32\u0e2a\u0e4c \u0e04\u0e35\u0e22\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038441\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e2a\u0e40\u0e0b\u0e34\u0e25 \u0e44\u0e2d\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038441 \u0e1a\u0e08.\u0e04\u0e32\u0e2a\u0e40\u0e0b\u0e34\u0e25 \u0e44\u0e2d\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e44\u0e2d\u0e17\u0e35  \u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e01\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91\/115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038459\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e2a \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47891\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47891\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038459 \u0e1a\u0e08.\u0e08\u0e31\u0e2a \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 47891 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e2a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e25\u0e33\u0e42\u0e1e\u0e07 \u0e2b\u0e39\u0e1f\u0e31\u0e07 \u0e2a\u0e32\u0e22\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e40\u0e21\u0e32\u0e2a\u0e4c \u0e04\u0e35\u0e22\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009696\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e44\u0e17\u0e22 \u0e04\u0e39\u0e0b\u0e35\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009696 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e44\u0e17\u0e22 \u0e04\u0e39\u0e0b\u0e35\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 91\/18-91\/19  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003973\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35\u0e42\u0e2d \u0e04\u0e49\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003973 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35\u0e42\u0e2d \u0e04\u0e49\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 82\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569007617\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e1a\u0e42\u0e2d\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007617 \u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e1a\u0e42\u0e2d\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e40\u0e2b\u0e47\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0505569016495\",\"name_th\":\"\u0e1a\u0e08. \u0e0b\u0e2d\u0e22 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016495 \u0e1a\u0e08. \u0e0b\u0e2d\u0e22 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 62012 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a pos \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19 qr code \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e2d\u0e07\u0e42\u0e15\u0e4a\u0e30\u0e1c\u0e48\u0e32\u0e19 line \u0e41\u0e25\u0e30ai \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c it \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u60c5\u5831\u901a\u4fe1\u30fbit 1\/4  \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e41\u0e01\u0e49\u0e27\u0e19\u0e27\u0e23\u0e31\u0e10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016541\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e32 \u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016541 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e32 \u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21  \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e31\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 83\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000783\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e32\u0e0d\u0e21\u0e07\u0e04\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000783 \u0e2b\u0e08.\u0e2b\u0e32\u0e0d\u0e21\u0e07\u0e04\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-22 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 135  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001706\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e17\u0e39\u0e1e\u0e25\u0e31\u0e2a \u0e25\u0e35\u0e40\u0e01\u0e34\u0e49\u0e25 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001706 \u0e1a\u0e08.\u0e21\u0e35\u0e17\u0e39\u0e1e\u0e25\u0e31\u0e2a \u0e25\u0e35\u0e40\u0e01\u0e34\u0e49\u0e25 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e43\u0e14\u0e46 \u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e28\u0e32\u0e25 \u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e42\u0e15\u0e15\u0e38\u0e25\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 308\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0653569001177\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001177 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 2569-07-22 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 235  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e07\u0e01\u0e23\u0e30\u0e1a\u0e32\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0773569000447\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e31\u0e1a\u0e17\u0e2d\u0e07\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0773569000447 \u0e2b\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e31\u0e1a\u0e17\u0e2d\u0e07 2569-07-22 2000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 269\/62  \u0e16\u0e19\u0e19\u0e40\u0e01\u0e32\u0e30\u0e2b\u0e25\u0e31\u0e01 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569013493\",\"name_th\":\"\u0e1a\u0e08.88 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e44\u0e19\u0e17\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013493 \u0e1a\u0e08.88 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e44\u0e19\u0e17\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e25\u0e47\u0e2d\u0e01 \u0e41\u0e1c\u0e07\u0e04\u0e49\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 64\/15  \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e07\u0e04\u0e4c \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013507\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013507 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 274\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013523\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e17\u0e32\u0e23\u0e48\u0e32 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013523 \u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e17\u0e32\u0e23\u0e48\u0e32 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e23\u0e4c\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38\/115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010681\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e27\u0e34\u0e2a\u0e15\u0e49\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010681 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e27\u0e34\u0e2a\u0e15\u0e49\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010711\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e17\u0e39\u0e23\u0e48\u0e32 \u0e40\u0e23\u0e14 \u0e44\u0e25\u0e17\u0e4c \u0e40\u0e17\u0e2d\u0e23\u0e32\u0e1e\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010711 \u0e1a\u0e08.\u0e40\u0e19\u0e17\u0e39\u0e23\u0e48\u0e32 \u0e40\u0e23\u0e14 \u0e44\u0e25\u0e17\u0e4c \u0e40\u0e17\u0e2d\u0e23\u0e32\u0e1e\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e1a\u0e33\u0e1a\u0e31\u0e14, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c,\u0e1c\u0e49\u0e32\u0e1e\u0e22\u0e38\u0e07\u0e41\u0e02\u0e19 \u0e2b\u0e31\u0e27\u0e40\u0e02\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e19\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010788\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010788 \u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 2000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e0d\u52d5\u7523 4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569136851\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e27\u0e34\u0e2a\u0e15\u0e32 \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136851 \u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e27\u0e34\u0e2a\u0e15\u0e32 \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 14\/48   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 202 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 69 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136877\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136877 \u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 5\/29  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e23\u0e32\u0e27\u0e34\u0e40\u0e17\u0e35\u0e22\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136923\",\"name_th\":\"\u0e1a\u0e08.\u0e2a.\u0e08\u0e23\u0e31\u0e2a\u0e41\u0e2a\u0e07\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136923 \u0e1a\u0e08.\u0e2a.\u0e08\u0e23\u0e31\u0e2a\u0e41\u0e2a\u0e07\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 225\/1-2  \u0e0b\u0e2d\u0e22 \u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136931\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e19\u0e25\u0e35\u0e48 \u0e2a\u0e40\u0e15\u0e22\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136931 \u0e1a\u0e08.\u0e42\u0e2d\u0e19\u0e25\u0e35\u0e48 \u0e2a\u0e40\u0e15\u0e22\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 38\/23  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137008\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e1e\u0e35\u0e1e\u0e35 360 \u0e17\u0e34\u0e0a\u0e0a\u0e39 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17091\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17091\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137008 \u0e1a\u0e08.\u0e08\u0e35\u0e1e\u0e35\u0e1e\u0e35 360 \u0e17\u0e34\u0e0a\u0e0a\u0e39 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 17091 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0a\u0e33\u0e23\u0e30 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e0a\u0e47\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e0a\u0e47\u0e14\u0e21\u0e37\u0e2d \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e16\u0e38\u0e07\u0e02\u0e22\u0e30 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 88\/196  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137016\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e42\u0e01\u0e1a\u0e38\u0e40\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137016 \u0e1a\u0e08.\u0e2e\u0e32\u0e42\u0e01\u0e1a\u0e38\u0e40\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e35\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e36\u0e48\u0e1b\u0e38\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 48  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 42 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137024\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e27\u0e23\u0e34\u0e28 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77306\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77306\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137024 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e27\u0e23\u0e34\u0e28 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 77306 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c (printer) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e31\u0e25\u0e15\u0e34\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e41\u0e01\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 23\/3  \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e010010 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137172\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e0a\u0e34\u0e23\u0e30 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137172 \u0e1a\u0e08.\u0e2d\u0e0a\u0e34\u0e23\u0e30 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 14\/54  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 69 (\u0e17\u0e33\u0e40\u0e19\u0e35\u0e22\u0e1a) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137202\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e41\u0e21\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137202 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e41\u0e21\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c111  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1924-2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137261\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e40\u0e14\u0e22\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137261 \u0e1a\u0e08.\u0e2e\u0e32\u0e40\u0e14\u0e22\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184\/162  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1f\u0e2d\u0e23\u0e31\u0e48\u0e21 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e41\u0e1a\u0e1a g \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137296\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137296 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e40\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c 111 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137393\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e27\u0e04\u0e39\u0e04\u0e39\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137393 \u0e1a\u0e08.\u0e40\u0e04\u0e27\u0e04\u0e39\u0e04\u0e39\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79  \u0e0b\u0e2d\u0e22 \u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02 26 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137521\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19 \u0e42\u0e04\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137521 \u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19 \u0e42\u0e04\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e3a\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 6  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 12 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024122\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e41\u0e17\u0e23\u0e4a\u0e01 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024122 \u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e41\u0e17\u0e23\u0e4a\u0e01 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e4d\u0e49\u0e32 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027458\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e40\u0e0b\u0e19\u0e34\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027458 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e40\u0e0b\u0e19\u0e34\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 26  \u0e0b\u0e2d\u0e22 \u0e23\u0e13\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e34\u0e0a\u0e31\u0e22 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027474\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e42\u0e2d (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"26512\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"26512\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027474 \u0e1a\u0e08.\u0e0b\u0e35\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e42\u0e2d (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 26512 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 (displaying) \u0e01\u0e32\u0e23\u0e0a\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19 (indicating) \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01 \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e31\u0e27\u0e41\u0e1b\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e19 \u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28 \u0e01\u0e32\u0e23\u0e40\u0e1c\u0e32\u0e44\u0e2b\u0e21\u0e49 \u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25 \u0e23\u0e30\u0e14\u0e31\u0e1a \u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e37\u0e14 (viscosity) \u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e32\u0e41\u0e19\u0e48\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e14 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e14\u0e1c\u0e25\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e1b\u0e15\u0e34\u0e04\u0e31\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 (\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27 (fluid meters) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e31\u0e1a (counting devices) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e32\u0e14\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 99\/9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s-06 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002551\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52101\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52101\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002551 \u0e2b\u0e08.\u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19 2569-07-21 2000000 52101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 37\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002577\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25\u0e40\u0e1f\u0e23\u0e0a \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52101\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52101\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002577 \u0e2b\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25\u0e40\u0e1f\u0e23\u0e0a \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-21 2000000 52101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 37\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022413\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1b\u0e48\u0e23\u0e38\u0e48\u0e22 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022413 \u0e1a\u0e08.\u0e44\u0e1b\u0e48\u0e23\u0e38\u0e48\u0e22 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/609  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e32\u0e22 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022430\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e14\u0e35\u0e49 \u0e17\u0e31\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022430 \u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e14\u0e35\u0e49 \u0e17\u0e31\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e0a\u0e47\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0a\u0e33\u0e23\u0e30 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e1c\u0e49\u0e32\u0e40\u0e0a\u0e47\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e35\u0e22\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e21\u0e32\u0e08\u0e32\u0e01\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022464\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e19\u0e0b\u0e34\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022464 \u0e1a\u0e08.\u0e0b\u0e38\u0e19\u0e0b\u0e34\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 23\/226  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004768\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e08\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004768 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e08\u0e35\u0e40\u0e2d\u0e2a\u0e44\u0e2d \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 65\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569038122\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 419 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038122 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 419 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 453\/281  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038131\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e21\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038131 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e21\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e0d\u52d5\u7523 417\/86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038157\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04\u0e27\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038157 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04\u0e27\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e16\u0e19\u0e19\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32 \u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u5efa\u8a2d 241\/86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038181\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 310 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038181 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 310 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 453\/248  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038254\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04 \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25932\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25932\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038254 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04 \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 25932 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e1a\u0e32\u0e19\u0e1e\u0e31\u0e1a \u0e23\u0e32\u0e07\u0e25\u0e34\u0e49\u0e19\u0e0a\u0e31\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 38\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038262\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e01\u0e23\u0e35\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038262 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e01\u0e23\u0e35\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e22\u0e32\u0e2a\u0e39\u0e1a \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e14 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 390\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007528\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e25\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007528 \u0e1a\u0e08.\u0e01\u0e31\u0e25\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e44\u0e02\u0e48\u0e21\u0e38\u0e01 \u0e2b\u0e25\u0e2d\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e01\u0e49\u0e27\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/14-15,90\/16,90\/17,90\/18  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007544\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e19\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007544 \u0e1a\u0e08.\u0e04\u0e19\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 217  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001961\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001961 \u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e22\u0e34\u0e21 \u82b8\u8853\u30fb\u5a2f\u697d 37\/29-32  \u0e16\u0e19\u0e19\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0475569001634\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001634 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0483569000547\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e1a\u0e32\u0e23\u0e21\u0e35 (2569) \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000547 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e1a\u0e32\u0e23\u0e21\u0e35 (2569) \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-21 2000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0503569005106\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e22\u0e32\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 1996\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005106 \u0e2b\u0e08.\u0e0a\u0e22\u0e32\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 1996 2569-07-21 2000000 43221 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e49\u0e21\u0e19\u0e49\u0e33\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 85\/9  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e31\u0e19\u0e15\u0e49\u0e19\u0e01\u0e2d\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016410\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016410 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 31\/32  \u0e16\u0e19\u0e19\u0e17\u0e38\u0e48\u0e07\u0e42\u0e2e\u0e40\u0e15\u0e47\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569002239\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e14\u0e35 \u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002239 \u0e2b\u0e08.\u0e40\u0e04\u0e14\u0e35 \u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-21 2000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e17\u0e33 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e27\u0e17\u0e4c\u0e2d\u0e34\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e25\u0e2d\u0e22\u0e15\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e19\u0e0a\u0e4c\u0e41\u0e01\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 97\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004691\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004691 \u0e1a\u0e08.\u0e40\u0e0b\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e14\u0e49\u0e27\u0e22\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 34\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0635569001497\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e23 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001497 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e23 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 577  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0723569000706\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e49\u0e32\u0e43\u0e2a \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000706 \u0e2b\u0e08.\u0e1f\u0e49\u0e32\u0e43\u0e2a \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b 2569-07-21 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23  \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 (\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e21\u0e04\u0e2d\u0e31\u0e1e) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569003065\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e25\u0e32\u0e22\u0e2d\u0e34\u0e48\u0e07 \u0e23\u0e39\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e30\u0e2d\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003065 \u0e1a\u0e08.\u0e1f\u0e25\u0e32\u0e22\u0e2d\u0e34\u0e48\u0e07 \u0e23\u0e39\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e30\u0e2d\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 25\/119  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e21\u0e2d\u0e42\u0e1e\u0e23\u0e07 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0845569010630\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e23\u0e23\u0e29\u0e32 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010630 \u0e1a\u0e08.\u0e2b\u0e23\u0e23\u0e29\u0e32 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 81100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 78\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010656\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e07\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e42\u0e20\u0e0a\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010656 \u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e07\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e42\u0e20\u0e0a\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 111\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569136052\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e07\u0e01\u0e49\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136052 \u0e1a\u0e08.\u0e04\u0e2d\u0e07\u0e01\u0e49\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 580\/81  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 87 (\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136109\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e1e\u0e35 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136109 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e1e\u0e35 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 68201 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u4e0d\u52d5\u7523 345\/20  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e38\u0e02\u0e2a\u0e1a\u0e32\u0e22 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136125\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e43\u0e08 1983 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136125 \u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e43\u0e08 1983 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d \u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/241  \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e41\u0e01\u0e07\u0e32\u0e2114 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136273\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e40\u0e27\u0e19\u0e42\u0e15 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136273 \u0e1a\u0e08.\u0e25\u0e32\u0e40\u0e27\u0e19\u0e42\u0e15 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 725  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e42\u0e17\u0e23  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 114 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136354\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e2e\u0e31\u0e1a\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136354 \u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e2e\u0e31\u0e1a\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 725  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e42\u0e17\u0e23  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 175 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136397\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e04 \u0e25\u0e48\u0e33\u0e0b\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136397 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e04 \u0e25\u0e48\u0e33\u0e0b\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 11\/157  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136435\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e35\u0e48\u0e21\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136435 \u0e1a\u0e08.\u0e22\u0e35\u0e48\u0e21\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 440\/2  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e27\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136451\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e40\u0e27 \u0e17\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136451 \u0e1a\u0e08.\u0e0a\u0e40\u0e27 \u0e17\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e31\u0e14\u0e40\u0e25\u0e47\u0e1a \u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e41\u0e15\u0e48\u0e07\u0e02\u0e19 \u0e42\u0e01\u0e19\u0e02\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e38\u0e19\u0e31\u0e02 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 1198\/1-2  \u0e16\u0e19\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136516\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e30\u0e1e\u0e34\u0e41\u0e0b\u0e04\u0e04\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136516 \u0e1a\u0e08.\u0e40\u0e2d\u0e30\u0e1e\u0e34\u0e41\u0e0b\u0e04\u0e04\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 44\/33  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 46 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136770\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e35\u0e22 \u0e42\u0e23\u0e21\u0e48\u0e32 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136770 \u0e1a\u0e08.\u0e40\u0e27\u0e35\u0e22 \u0e42\u0e23\u0e21\u0e48\u0e32 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 233  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023975\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e0b\u0e27\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023975 \u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e0b\u0e27\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33 \u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c) \u60c5\u5831\u901a\u4fe1\u30fbit 2070   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 104 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023991\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e25\u0e39\u0e23\u0e32 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023991 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e25\u0e39\u0e23\u0e32 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 400  \u0e16\u0e19\u0e19\u0e28\u0e34\u0e23\u0e34\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027407\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e07\u0e0b\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027407 \u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e07\u0e0b\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 99\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022359\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022359 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 9\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022405\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e25\u0e27\u0e4c\u0e27\u0e31\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022405 \u0e1a\u0e08.\u0e42\u0e1f\u0e25\u0e27\u0e4c\u0e27\u0e31\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46105 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\/\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e4d\u0e49\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569037860\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e27\u0e35\u0e40\u0e0b\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037860 \u0e1a\u0e08.\u0e04\u0e35\u0e27\u0e35\u0e40\u0e0b\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 460\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037878\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e0a\u0e32 \u0e1b\u0e25\u0e32\u0e17\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037878 \u0e1a\u0e08.\u0e23\u0e32\u0e0a\u0e32 \u0e1b\u0e25\u0e32\u0e17\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 175  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037932\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2b\u0e22\u0e32\u0e07 \u0e19\u0e34\u0e27\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23939\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23939\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037932 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2b\u0e22\u0e32\u0e07 \u0e19\u0e34\u0e27\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 23939 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e19\u0e32\u0e42\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e19\u0e32\u0e42\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u88fd\u9020 9\/27-28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009602\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e17\u0e23\u0e32 \u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009602 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e17\u0e23\u0e32 \u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 71102 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 181\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0223569000352\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e19\u0e34\u0e20\u0e32 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000352 \u0e2b\u0e08.\u0e1e\u0e23\u0e19\u0e34\u0e20\u0e32 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 2569-07-20 2000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1e\u0e32\u0e22 \u0e40\u0e04\u0e49\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 24\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0415569003785\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003785 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 555\/53  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e0a\u0e22\u0e32-\u0e19\u0e32\u0e14\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e19\u0e32\u0e14\u0e35 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0433569000440\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19 \u0e0b\u0e35 \u0e41\u0e21\u0e0a\u0e0b\u0e35\u0e19  \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000440 \u0e2b\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19 \u0e0b\u0e35 \u0e41\u0e21\u0e0a\u0e0b\u0e35\u0e19  \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 2569-07-20 2000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 218\/1   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 218\/1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e48\u0e32\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e16\u0e19\u0e19\u0e21\u0e35\u0e0a\u0e31\u0e22 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0475569001626\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e0b\u0e19\u0e2e\u0e07\u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001626 \u0e1a\u0e08. \u0e40\u0e0b\u0e19\u0e2e\u0e07\u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e21\u0e49\u0e27\u0e35\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e44\u0e21\u0e49\u0e2a\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07\u0e44\u0e21\u0e49\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 13 \u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e32\u0e21\u0e21\u0e15\u0e34\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e22\u0e39\u0e04\u0e32\u0e25\u0e34\u0e1b\u0e15\u0e31\u0e2a \u0e2a\u0e30\u0e40\u0e14\u0e32\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2a\u0e19\u0e17\u0e30\u0e40\u0e25 \u0e2a\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e01\u0e23\u0e30\u0e16\u0e34\u0e19\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e30\u0e16\u0e34\u0e19\u0e40\u0e17\u0e1e\u0e32 \u0e01\u0e23\u0e30\u0e16\u0e34\u0e19\u0e22\u0e31\u0e01\u0e29\u0e4c \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e21\u0e30\u0e02\u0e32\u0e21 \u0e21\u0e30\u0e44\u0e1f\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e30\u0e1b\u0e23\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e32\u0e21\u0e08\u0e38\u0e23\u0e35 \u0e44\u0e21\u0e49\u0e15\u0e32\u0e25 \u88fd\u9020 122  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e19\u0e34\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e17\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004683\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e21\u0e0b\u0e35\u0e25 \u0e41\u0e25\u0e47\u0e1a\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004683 \u0e1a\u0e08.\u0e40\u0e04\u0e21\u0e0b\u0e35\u0e25 \u0e41\u0e25\u0e47\u0e1a\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 71201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 392  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569002167\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e0d\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002167 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e0d\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e07\u0e42\u0e09\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e1a\u0e39\u0e48 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e22\u0e32\u0e2a\u0e35\u0e1f\u0e31\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0733569001087\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e1f\u0e23\u0e0a \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52101\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52101\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001087 \u0e2b\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e1f\u0e23\u0e0a \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-20 2000000 52101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0733569001095\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e42\u0e19\u0e27\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52101\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52101\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001095 \u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e42\u0e19\u0e27\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-20 2000000 52101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007621\",\"name_th\":\"\u0e1a\u0e08.\u0e07\u0e32\u0e21\u0e16\u0e32\u0e27\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007621 \u0e1a\u0e08.\u0e07\u0e32\u0e21\u0e16\u0e32\u0e27\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e07\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e07\u0e32\u0e19\u0e1b\u0e39\u0e19\u0e09\u0e32\u0e1a \u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07  \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2d\u0e34\u0e10 \u0e07\u0e32\u0e19\u0e44\u0e21\u0e49 \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1c\u0e19\u0e31\u0e07\u0e21\u0e48\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 189\/252,189\/253  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007630\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e38\u0e19\u0e27\u0e35\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007630 \u0e1a\u0e08.\u0e25\u0e38\u0e19\u0e27\u0e35\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e41\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 54\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007648\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e01\u0e27\u0e35 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24109\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24109\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007648 \u0e1a\u0e08.\u0e01\u0e23\u0e01\u0e27\u0e35 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 24109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e4a\u0e21 \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e1e\u0e31\u0e1a \u0e15\u0e31\u0e14 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e01\u0e25\u0e36\u0e07 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 22\/100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013361\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013361 \u0e1a\u0e08.\u0e19\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 2\/127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013388\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e32\u0e22 \u0e40\u0e1f\u0e23\u0e0a\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013388 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e32\u0e22 \u0e40\u0e1f\u0e23\u0e0a\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e19\u0e04\u0e23\u0e31\u0e27 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07   \u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013396\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e15\u0e15\u0e34\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013396 \u0e1a\u0e08.\u0e40\u0e1a\u0e15\u0e15\u0e34\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 78\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010575\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e2a\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e4a\u0e01 \u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010575 \u0e1a\u0e08.\u0e44\u0e2d\u0e2a\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e4a\u0e01 \u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 12\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010583\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e23\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010583 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e23\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 170\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0945569000757\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000757 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 60\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0103569007757\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e31\u0e14\u0e0a\u0e32 \u0e19\u0e27\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96305\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96305\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007757 \u0e2b\u0e08.\u0e1e\u0e31\u0e14\u0e0a\u0e32 \u0e19\u0e27\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32 2569-07-19 2000000 96305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e2d\u0e1a\u0e19\u0e27\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 170\/65  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2758 \u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e19\u0e15\u0e4c1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007765\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e0b\u0e35 \u0e2a\u0e1b\u0e32\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96305\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96305\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007765 \u0e2b\u0e08.\u0e1e\u0e35\u0e0b\u0e35 \u0e2a\u0e1b\u0e32 2569-07-19 2000000 96305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e2d\u0e1a\u0e19\u0e27\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 170\/65  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2758 (\u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e19\u0e15\u0e4c1) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135960\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135960 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 2000000 46699 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 641\/98  \u0e16\u0e19\u0e19\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023851\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e14\u0e35\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023851 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e14\u0e35\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 2000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 306\/8  \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e15\u0e30\u0e40\u0e04\u0e47\u0e14\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569037827\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e42\u0e25\u0e23\u0e48\u0e32 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11044\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11044\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037827 \u0e1a\u0e08.\u0e40\u0e27\u0e42\u0e25\u0e23\u0e48\u0e32 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 2000000 11044 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e0a\u0e39\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u88fd\u9020 80\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0905569005911\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005911 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u4e0d\u52d5\u7523 36\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e2b\u0e07\u0e2a\u0e4c \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e2d\u0e48\u0e2d\u0e19\u0e2b\u0e27\u0e32\u0e19 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569135781\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e27\u0e47\u0e04\u0e0b\u0e34\u0e27\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135781 \u0e1a\u0e08.\u0e41\u0e27\u0e47\u0e04\u0e0b\u0e34\u0e27\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e42\u0e23\u0e04 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e34\u0e15\u0e43\u0e08\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u533b\u7642\u30fb\u798f\u7949 860\/49 \u0e15\u0e23\u0e2d\u0e01\u0e27\u0e31\u0e14\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e43\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135811\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e27\u0e35\u0e40\u0e04 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135811 \u0e1a\u0e08.\u0e0b\u0e35\u0e27\u0e35\u0e40\u0e04 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e4d\u0e32\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 198\/96  \u0e0b\u0e2d\u0e22 \u0e2a\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e20\u0e32 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135854\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e44\u0e27\u0e1f\u0e4c \u0e22\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135854 \u0e1a\u0e08.\u0e23\u0e35\u0e44\u0e27\u0e1f\u0e4c \u0e22\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e0b\u0e2d\u0e22 \u0e40\u0e22\u0e47\u0e19\u0e08\u0e34\u0e15 10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027164\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e1e\u0e35 \u0e27\u0e2d\u0e22\u0e22\u0e32\u0e08  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027164 \u0e1a\u0e08.\u0e40\u0e08 \u0e1e\u0e35 \u0e27\u0e2d\u0e22\u0e22\u0e32\u0e08  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e1a\u0e1a\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e21\u0e31\u0e04\u0e04\u0e38\u0e40\u0e17\u0e28\u0e01\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 168\/57  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e34\u0e23\u0e01\u0e32\u0e19\u0e15\u0e4c2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 7 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022103\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e1e\u0e23\u0e23\u0e14\u0e34\u0e2b\u0e22\u0e01\u0e2b\u0e19\u0e38\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022103 \u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e1e\u0e23\u0e23\u0e14\u0e34\u0e2b\u0e22\u0e01\u0e2b\u0e19\u0e38\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e04\u0e21\u0e1b\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e25\u0e30\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u6559\u80b2 18\/500  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022146\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e49\u0e32\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c  \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022146 \u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e49\u0e32\u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c  \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07-\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569037789\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037789 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 88\/102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0355569000400\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0355569000400 \u0e1a\u0e08.\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e1b\u0e31\u0e01\u0e40\u0e2a\u0e32\u0e1e\u0e32\u0e14\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0643569000511\",\"name_th\":\"\u0e2b\u0e08.\u0e10\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0643569000511 \u0e2b\u0e08.\u0e10\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-18 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0815569002157\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e32\u0e14\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002157 \u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e32\u0e14\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 999\/144  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0103569007633\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e18\u0e19\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e41\u0e04\u0e25\u0e0a\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007633 \u0e2b\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e18\u0e19\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e41\u0e04\u0e25\u0e0a 2569-07-17 2000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/85  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 69 \u0e41\u0e22\u0e01 22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134971\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e21\u0e2a\u0e4c  \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46492\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46492\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134971 \u0e1a\u0e08.\u0e40\u0e08\u0e21\u0e2a\u0e4c  \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 46492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 981  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c\u0e2d\u0e34\u0e19\u0e19\u0e4c\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2a\u0e35\u0e25\u0e21\u0e0a\u0e47\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e25\u0e47\u0e2d\u0e1a\u0e1a\u0e35\u0e49 1 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135030\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e25\u0e35 \u0e1f\u0e39\u0e14 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135030 \u0e1a\u0e08.\u0e27\u0e25\u0e35 \u0e1f\u0e39\u0e14 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e38\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32\u0e44\u0e17\u0e22 \u0e0b\u0e2d\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e2a\u0e49\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e40\u0e2a\u0e49\u0e19\u0e1a\u0e30\u0e2b\u0e21\u0e35\u0e48 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 206  \u0e0b\u0e2d\u0e22 \u0e27\u0e0a\u0e34\u0e23\u0e18\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e18\u0e34\u0e15 55 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135048\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e07\u0e40\u0e08\u0e35\u0e22\u0e07 \u0e09\u0e27\u0e19\u0e40\u0e2b\u0e21\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135048 \u0e1a\u0e08.\u0e0a\u0e34\u0e07\u0e40\u0e08\u0e35\u0e22\u0e07 \u0e09\u0e27\u0e19\u0e40\u0e2b\u0e21\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47190 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 146\/80  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27122(\u0e21\u0e2b\u0e32\u0e14\u0e44\u0e17\u0e221) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135111\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e1b\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135111 \u0e1a\u0e08.\u0e0a\u0e34\u0e1b\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/66  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 19 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135129\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e1f \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135129 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e1f \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135137\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e1a\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135137 \u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e1a\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135145\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135145 \u0e1a\u0e08.\u0e40\u0e17\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135153\",\"name_th\":\"\u0e1a\u0e08.\u0e15.\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135153 \u0e1a\u0e08.\u0e15.\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135161\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e1f \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135161 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e1f \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135170\",\"name_th\":\"\u0e1a\u0e08.789 \u0e2a\u0e19\u0e38\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135170 \u0e1a\u0e08.789 \u0e2a\u0e19\u0e38\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e19\u0e38\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e01\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135188\",\"name_th\":\"\u0e1a\u0e08.99 \u0e2a\u0e19\u0e38\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135188 \u0e1a\u0e08.99 \u0e2a\u0e19\u0e38\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135196\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e15\u0e31\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135196 \u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e15\u0e31\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135200\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e2d\u0e34\u0e19 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135200 \u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e2d\u0e34\u0e19 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135218\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e2a\u0e15\u0e34\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135218 \u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e2a\u0e15\u0e34\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e19\u0e42\u0e01\u0e49 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e1a\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135269\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e27\u0e35 \u0e04\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135269 \u0e1a\u0e08.\u0e42\u0e23\u0e27\u0e35 \u0e04\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 32309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e21\u0e49\u0e04\u0e34\u0e27\u0e2a\u0e19\u0e38\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e44\u0e21\u0e49\u0e04\u0e34\u0e27\u0e1e\u0e39\u0e25  \u0e44\u0e21\u0e49\u0e04\u0e34\u0e27\u0e1a\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 350\/3  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e27\u0e34\u0e19\u0e17\u0e27\u0e07\u0e28\u0e4c 28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135374\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e38\u0e2a \u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135374 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e38\u0e2a \u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07 ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 3656\/45  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e01\u0e23\u0e35\u0e19\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 15 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135404\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e01\u0e40\u0e19\u0e2a\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135404 \u0e1a\u0e08.\u0e41\u0e2d\u0e01\u0e40\u0e19\u0e2a\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 53\/1  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 53 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135421\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47741\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47741\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135421 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e38\u0e17\u0e18\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47741 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e39\u0e0a\u0e32 \u0e08\u0e33\u0e19\u0e33\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118\/16  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 74 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135498\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e2a\u0e4c\u0e40\u0e0b\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135498 \u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e2a\u0e4c\u0e40\u0e0b\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01 \u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 65\/42  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 70 (\u0e0a\u0e39\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e2f) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135501\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e42\u0e15\u0e40\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135501 \u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e42\u0e15\u0e40\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e38\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 144  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 80 \u0e41\u0e22\u0e01 20 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023622\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e40\u0e04\u0e47\u0e19 \u0e1e\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023622 \u0e1a\u0e08.\u0e42\u0e17\u0e40\u0e04\u0e47\u0e19 \u0e1e\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 9\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023673\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e40\u0e22\u0e32\u0e27\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28230\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28230\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023673 \u0e1a\u0e08.\u0e1e\u0e40\u0e22\u0e32\u0e27\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 28230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e09\u0e35\u0e14 \u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1b\u0e31\u0e4a\u0e21\u0e42\u0e25\u0e2b\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 888\/112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023690\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e41\u0e1e\u0e19\u0e14\u0e49\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023690 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e41\u0e1e\u0e19\u0e14\u0e49\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 89\/247  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027075\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e25\u0e34\u0e4a\u0e01 \u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e40\u0e17\u0e04\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027075 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e25\u0e34\u0e4a\u0e01 \u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e40\u0e17\u0e04\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027121\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e04\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027121 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e04\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002625\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002625 \u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 35\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003122\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003122 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c 2569-07-17 2000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 68\/149  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e25\u0e34\u0e25 \u0e41\u0e25\u0e19\u0e0b\u0e35\u0e42\u0e2d \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e0b\u0e2d\u0e22 \u0e17\u0e38\u0e48\u0e07\u0e01\u0e25\u0e21\u0e15\u0e32\u0e25\u0e2b\u0e21\u0e31\u0e19 \u0e16\u0e19\u0e19\u0e17\u0e38\u0e48\u0e07\u0e01\u0e25\u0e21\u0e15\u0e32\u0e25\u0e2b\u0e21\u0e31\u0e19 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037568\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e27\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037568 \u0e1a\u0e08.\u0e19\u0e32\u0e27\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 999\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037614\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2b\u0e22\u0e48\u0e27\u0e04\u0e31\u0e07\u0e15\u0e35\u0e49\u0e1c\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037614 \u0e1a\u0e08.\u0e42\u0e2b\u0e22\u0e48\u0e27\u0e04\u0e31\u0e07\u0e15\u0e35\u0e49\u0e1c\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e37\u0e49\u0e19 \u88fd\u9020 238\/243  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e17\u0e32\u0e27\u0e19\u0e4c 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037622\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e22\u0e2d\u0e32\u0e23\u0e4c\u0e21 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037622 \u0e1a\u0e08.\u0e19\u0e32\u0e22\u0e2d\u0e32\u0e23\u0e4c\u0e21 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037657\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037657 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 74\/197  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0235569000427\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e1a\u0e32 \u0e40\u0e25\u0e32\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0235569000427 \u0e1a\u0e08.\u0e04\u0e39\u0e1a\u0e32 \u0e40\u0e25\u0e32\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 56101 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e2a\u0e31\u0e48\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19  \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0323569000556\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 999\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000556 \u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 999 2569-07-17 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0415569003751\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e40\u0e27\u0e35\u0e22\u0e23\u0e4c \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003751 \u0e1a\u0e08.\u0e27\u0e32\u0e40\u0e27\u0e35\u0e22\u0e23\u0e4c \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d \u0e1c\u0e39\u0e49\u0e02\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 255\/31  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0475569001596\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e09\u0e34\u0e19 \u0e08\u0e34\u0e19 \u0e40\u0e1f\u0e34\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001596 \u0e1a\u0e08.\u0e40\u0e09\u0e34\u0e19 \u0e08\u0e34\u0e19 \u0e40\u0e1f\u0e34\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001600\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e34\u0e49\u0e07 \u0e40\u0e2b\u0e22\u0e35\u0e22\u0e19 \u0e0b\u0e38\u0e48\u0e19 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001600 \u0e1a\u0e08.\u0e40\u0e08\u0e34\u0e49\u0e07 \u0e40\u0e2b\u0e22\u0e35\u0e22\u0e19 \u0e0b\u0e38\u0e48\u0e19 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0493569000407\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e1d\u0e19 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0493569000407 \u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e1d\u0e19 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c 2569-07-17 2000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 164  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e48\u0e19\u0e04\u0e33\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016177\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e14\u0e32 \u0e42\u0e01\u0e23\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016177 \u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e14\u0e32 \u0e42\u0e01\u0e23\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0605569002124\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e38\u0e22\u0e1f\u0e34\u0e19\u0e40\u0e1f\u0e22\u0e1f\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002124 \u0e1a\u0e08.\u0e1f\u0e38\u0e22\u0e1f\u0e34\u0e19\u0e40\u0e1f\u0e22\u0e1f\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 114\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0675569001535\",\"name_th\":\"\u0e1a\u0e08.\u0e1c\u0e48\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001535 \u0e1a\u0e08.\u0e1c\u0e48\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 2\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007559\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e27 \u0e2d\u0e2d\u0e1f \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007559 \u0e1a\u0e08.\u0e19\u0e27 \u0e2d\u0e2d\u0e1f \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e (wellness center) \u533b\u7642\u30fb\u798f\u7949 111\/126  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e34\u0e19\u0e23\u0e14\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007567\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007567 \u0e1a\u0e08.\u0e1e\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/42  \u0e16\u0e19\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013281\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013281 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 86\/78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010516\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e0a\u0e32\u0e42\u0e14\u0e27\u0e4c \u0e42\u0e27\u0e22\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"50112\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"50112\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010516 \u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e0a\u0e32\u0e42\u0e14\u0e27\u0e4c \u0e42\u0e27\u0e22\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 50112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e32\u0e25\u0e33 \u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 33\/106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010524\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e1a\u0e32\u0e22 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010524 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e1a\u0e32\u0e22 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22 \u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e33 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49 \u4e0d\u52d5\u7523 16\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010532\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e42\u0e0b\u0e44\u0e0b\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93299\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93299\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010532 \u0e1a\u0e08.\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e42\u0e0b\u0e44\u0e0b\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 2000000 93299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 (lifestyle) \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e41\u0e01\u0e48\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 78\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569134289\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e04\u0e32\u0e22\u0e32\u0e2a\u0e38 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134289 \u0e1a\u0e08.\u0e42\u0e2d\u0e04\u0e32\u0e22\u0e32\u0e2a\u0e38 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e25\u0e30\u0e44\u0e02\u0e21\u0e31\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 953 \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e40\u0e2d103 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 53 (\u0e44\u0e1b\u0e14\u0e35-\u0e21\u0e32\u0e14\u0e35) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134301\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e40\u0e2d\u0e0a \u0e41\u0e0b\u0e14 \u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134301 \u0e1a\u0e08.\u0e17\u0e35 \u0e40\u0e2d\u0e0a \u0e41\u0e0b\u0e14 \u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 877-879  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134351\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134351 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e19\u0e17\u0e38\u0e48\u0e19\u0e25\u0e2d\u0e22\u0e19\u0e49\u0e33 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e1b\u0e23\u0e21\u0e32\u0e13\u0e39 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e19\u0e49\u0e33\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e1c\u0e2a\u0e21\u0e40\u0e04\u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e19\u0e34\u0e04\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 98\/228  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 39 (\u0e40\u0e17\u0e1e\u0e25\u0e35\u0e25\u0e32 1) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134416\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2d\u0e27\u0e4c \u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134416 \u0e1a\u0e08.\u0e1e\u0e2d\u0e27\u0e4c \u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 11\/144  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e23\u0e32\u0e2a\u0e34\u0e23\u0e34 \u0e2a\u0e32\u0e17\u0e23-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134581\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e19\u0e15\u0e23\u0e32 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134581 \u0e1a\u0e08.\u0e21\u0e19\u0e15\u0e23\u0e32 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/221  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134602\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e25\u0e04\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"26109\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"26109\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134602 \u0e1a\u0e08.\u0e01\u0e34\u0e25\u0e04\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 26109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14 \u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e04\u0e48\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c (sensor) \u0e42\u0e1e\u0e23\u0e1a (probe) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 3  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134700\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e42\u0e22 \u0e44\u0e27 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134700 \u0e1a\u0e08.\u0e1e\u0e42\u0e22 \u0e44\u0e27 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e31\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e04\u0e39\u0e48 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e33\u0e14\u0e31\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e37\u0e1a\u0e27\u0e07\u0e28\u0e4c\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e0d\u0e32\u0e15\u0e34 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e01\u0e41\u0e25\u0e30\u0e40\u0e08\u0e32\u0e30\u0e15\u0e32\u0e21\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e02\u0e2d\u0e07 \u0e02\u0e31\u0e14\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e01\u0e38\u0e0d\u0e41\u0e08 \u0e2a\u0e30\u0e40\u0e14\u0e32\u0e30\u0e01\u0e38\u0e0d\u0e41\u0e08 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e23\u0e16\u0e44\u0e1b\u0e08\u0e2d\u0e14 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e31\u0e1a\u0e15\u0e48\u0e2d \u0e1e\u0e23\u0e1a. \u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 8  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 33 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134777\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e2a\u0e4c\u0e40\u0e0b\u0e23\u0e32 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134777 \u0e1a\u0e08.\u0e44\u0e27\u0e2a\u0e4c\u0e40\u0e0b\u0e23\u0e32 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 58202 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 202  \u0e16\u0e19\u0e19\u0e19\u0e32\u0e07\u0e25\u0e34\u0e49\u0e19\u0e08\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134891\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134891 \u0e1a\u0e08.\u0e2a\u0e38\u0e02 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 944  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e34\u0e15\u0e23\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s24052 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 24 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026753\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026753 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u6559\u80b2 117\/265   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026761\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026761 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e14\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 361  \u0e16\u0e19\u0e19\u0e1a\u0e2d\u0e19\u0e14\u0e4c\u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026788\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e4a\u0e15 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026788 \u0e1a\u0e08.\u0e41\u0e01\u0e4a\u0e15 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 445  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e1a\u0e2d\u0e19\u0e14\u0e4c\u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026800\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e04\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28219\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28219\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026800 \u0e1a\u0e08.\u0e44\u0e25\u0e04\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 28219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e30\u0e40\u0e17\u0e32\u0e30\u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e25\u0e39\u0e01\u0e22\u0e32\u0e07\u0e01\u0e30\u0e40\u0e17\u0e32\u0e30\u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u88fd\u9020 105\/406  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e23\u0e34\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e44\u0e25\u0e17\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021824\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e28\u0e23\u0e35\u0e23\u0e32\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10131\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10131\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021824 \u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e28\u0e23\u0e35\u0e23\u0e32\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 10131 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 101\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021921\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021921 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e23\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e2d\u0e23\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e2d\u0e23\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 36\/415  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569037452\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e1a\u0e25\u0e39 \u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"36002\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"36002\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037452 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e1a\u0e25\u0e39 \u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 36002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e16\u0e31\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 62\/285  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037479\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e2e\u0e2d\u0e23\u0e34\u0e0b\u0e2d\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037479 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e2e\u0e2d\u0e23\u0e34\u0e0b\u0e2d\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 315\/85   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3\/3 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037525\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e20\u0e27\u0e31\u0e15\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037525 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e20\u0e27\u0e31\u0e15\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e42\u0e14\u0e22\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 126\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0475569001588\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39 \u0e40\u0e08\u0e35\u0e4b\u0e22 \u0e2e\u0e38\u0e22 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001588 \u0e1a\u0e08.\u0e0b\u0e39 \u0e40\u0e08\u0e35\u0e4b\u0e22 \u0e2e\u0e38\u0e22 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000948\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d \u0e40\u0e2b\u0e2d \u0e2b\u0e22\u0e27\u0e19 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000948 \u0e1a\u0e08.\u0e44\u0e2d \u0e40\u0e2b\u0e2d \u0e2b\u0e22\u0e27\u0e19 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0505569016011\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e31\u0e19\u0e15\u0e4c \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016011 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e31\u0e19\u0e15\u0e4c \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e49\u0e32\u0e27\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 13\/10  \u0e0b\u0e2d\u0e22 2 \u0e16\u0e19\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001421\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e19\u0e1f\u0e34\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001421 \u0e1a\u0e08.\u0e1f\u0e34\u0e19\u0e1f\u0e34\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 192\/121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004616\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e30 \u0e04\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004616 \u0e1a\u0e08.\u0e41\u0e04\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e30 \u0e04\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 873\/19  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0775569003022\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e27\u0e31\u0e19 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003022 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e27\u0e31\u0e19 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 500\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569013191\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e42\u0e27\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e27\u0e31\u0e19 \u0e21\u0e27\u0e22 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013191 \u0e1a\u0e08.\u0e23\u0e35\u0e42\u0e27\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e27\u0e31\u0e19 \u0e21\u0e27\u0e22 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e15\u0e31\u0e27 \u0e21\u0e27\u0e22\u0e44\u0e17\u0e22 \u0e21\u0e27\u0e22\u0e2a\u0e32\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u6559\u80b2 49\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010508\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e44\u0e2d \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010508 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e44\u0e2d \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 (hospitality management) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e01\u0e48 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e42\u0e2e\u0e2a\u0e40\u0e17\u0e25 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u4e0d\u52d5\u7523 118\/4  \u0e2d\u0e32\u0e04\u0e32\u0e23patra  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 301 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005830\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e27 \u0e23\u0e31\u0e25 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005830 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e27 \u0e23\u0e31\u0e25 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 2000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 62\/4  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07 \u0e23.5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569133673\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e17\u0e41\u0e2d\u0e25 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66192\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66192\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133673 \u0e1a\u0e08.\u0e40\u0e0b\u0e17\u0e41\u0e2d\u0e25 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 66192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e41\u0e17\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u91d1\u878d\u30fb\u4fdd\u967a 72\/16  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133843\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e21\u0e19\u0e34-\u0e40\u0e2e\u0e25\u0e17\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133843 \u0e1a\u0e08.\u0e42\u0e2d\u0e21\u0e19\u0e34-\u0e40\u0e2e\u0e25\u0e17\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46441 \u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e1b\u0e01\u0e15\u0e34\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c. \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 399  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e19\u0e0821  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3329 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 33 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133878\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e1b\u0e32\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133878 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e1b\u0e32\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e23\u0e30\u0e27\u0e32\u0e19 \u0e16\u0e31\u0e48\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e19\u0e32\u0e19\u0e34\u0e04\u0e21 1 \u0e0b\u0e2d\u0e22 25 \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e19\u0e32\u0e19\u0e34\u0e04\u0e21 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133983\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e35\u0e14 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133983 \u0e1a\u0e08.\u0e25\u0e35\u0e14 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/58  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133991\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e01360 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133991 \u0e1a\u0e08.\u0e41\u0e2d\u0e01360 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 70209 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e01\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u0e42\u0e14\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e2d\u0e34\u0e2a\u0e23\u0e30\u0e17\u0e35\u0e48\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e35 23 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023410\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e40\u0e23\u0e42\u0e27 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023410 \u0e1a\u0e08.\u0e21\u0e34\u0e40\u0e23\u0e42\u0e27 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023444\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0a\u0e21\u0e1b\u0e4c\u0e40\u0e1b\u0e35\u0e49\u0e22\u0e19 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023444 \u0e1a\u0e08.\u0e41\u0e0a\u0e21\u0e1b\u0e4c\u0e40\u0e1b\u0e35\u0e49\u0e22\u0e19 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07  \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026524\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e21\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11049\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11049\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026524 \u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e21\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 11049 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e16\u0e19\u0e2d\u0e21\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e25\u0e07\u0e20\u0e32\u0e0a\u0e19\u0e30  \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e27\u0e14 \u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u88fd\u9020 119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021727\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e2d\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021727 \u0e1a\u0e08.\u0e08\u0e35\u0e2d\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021743\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021743 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 40\/2579  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021751\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e0b\u0e34\u0e19 \u0e40\u0e14\u0e04\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021751 \u0e1a\u0e08.\u0e22\u0e39\u0e0b\u0e34\u0e19 \u0e40\u0e14\u0e04\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/152-153   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3-303 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004661\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e32\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004661 \u0e1a\u0e08.\u0e40\u0e2d\u0e32\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e27\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32 \u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22\u0e42\u0e0b\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e08\u0e32\u0e30\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1b\u0e48\u0e32\u0e25\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569037312\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08.\u0e1a\u0e35.\u0e1e\u0e35. \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037312 \u0e1a\u0e08.\u0e40\u0e08.\u0e1a\u0e35.\u0e1e\u0e35. \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 144\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037321\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e32 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037321 \u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e32 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 8\/105   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 303 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037355\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34\u0e2e\u0e32\u0e27\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037355 \u0e1a\u0e08.\u0e14\u0e34\u0e2e\u0e32\u0e27\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 8\/105   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 204 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037410\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0d\u0e41\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037410 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0d\u0e41\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e42\u0e25\u0e2b\u0e30 \u0e2a\u0e32\u0e22\u0e2a\u0e25\u0e34\u0e07 \u0e25\u0e27\u0e14\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e25\u0e27\u0e14\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e40\u0e0a\u0e37\u0e2d\u0e01\u0e25\u0e27\u0e14 \u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002250\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e40\u0e2d\u0e2a. \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002250 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e40\u0e2d\u0e2a. \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e2b\u0e49\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e31\u0e01 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/297  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0233569000115\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e35\u0e44\u0e17\u0e22\u0e1f\u0e23\u0e38\u0e15\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0233569000115 \u0e2b\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e35\u0e44\u0e17\u0e22\u0e1f\u0e23\u0e38\u0e15\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 2569-07-15 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0245569003868\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e40\u0e1e\u0e35\u0e22\u0e27\u0e41\u0e01\u0e4a\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46613\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46613\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003868 \u0e1a\u0e08.\u0e44\u0e2e\u0e40\u0e1e\u0e35\u0e22\u0e27\u0e41\u0e01\u0e4a\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46613 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e4a\u0e32\u0e0b\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e4a\u0e32\u0e0b\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e44\u0e14\u0e2d\u0e2d\u0e01\u0e44\u0e0b\u0e14\u0e4c \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e41\u0e2b\u0e49\u0e07 \u0e01\u0e4a\u0e32\u0e0b\u0e44\u0e19\u0e42\u0e15\u0e23\u0e40\u0e08\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0475569001561\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39 \u0e0b\u0e27\u0e07 \u0e2b\u0e22\u0e34\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001561 \u0e1a\u0e08.\u0e0b\u0e39 \u0e0b\u0e27\u0e07 \u0e2b\u0e22\u0e34\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001570\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e31\u0e07 \u0e40\u0e08\u0e34\u0e49\u0e07 \u0e2b\u0e25\u0e07\u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001570 \u0e1a\u0e08.\u0e16\u0e31\u0e07 \u0e40\u0e08\u0e34\u0e49\u0e07 \u0e2b\u0e25\u0e07\u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000921\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29203\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29203\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000921 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 29203 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u88fd\u9020 83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0485569000930\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e35 \u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000930 \u0e1a\u0e08.\u0e09\u0e35 \u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e44\u0e17\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0655569002281\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002281 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 459\/353  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0705569003197\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e21\u0e42\u0e04\u0e23\u0e27\u0e32\u0e25\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003197 \u0e1a\u0e08.\u0e44\u0e21\u0e42\u0e04\u0e23\u0e27\u0e32\u0e25\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 58202 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \/ \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 124\/216  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e1d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08 9 \u0e16\u0e19\u0e19\u0e21\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e27\u0e07\u0e28\u0e4c \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003219\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10414\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10414\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003219 \u0e1a\u0e08.\u0e40\u0e25\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 10414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e01\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e40\u0e01\u0e25\u0e47\u0e14\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e43\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e40\u0e21\u0e47\u0e14\u0e01\u0e30\u0e25\u0e32\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e32\u0e01\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000676\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e27\u0e35\u0e1e\u0e35 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000676 \u0e2b\u0e08.\u0e17\u0e35\u0e27\u0e35\u0e1e\u0e35 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b 2569-07-15 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000684\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e15\u0e15\u0e34\u0e13\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000684 \u0e2b\u0e08.\u0e40\u0e15\u0e15\u0e34\u0e13 2569-07-15 2000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 107\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007133\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e20\u0e13 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007133 \u0e1a\u0e08.\u0e25\u0e20\u0e13 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (electric motorcycle) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007150\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a2\u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007150 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a2\u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01 \u0e2a\u0e01\u0e31\u0e14 \u0e40\u0e1e\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e08\u0e01 \u0e43\u0e2b\u0e49 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e44\u0e27\u0e49\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e31\u0e0d\u0e0a\u0e07 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e01\u0e31\u0e0d\u0e0a\u0e07 \u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14 \u0e22\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e22\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07 \u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e14\u0e49\u0e27\u0e22 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u8fb2\u6797\u6c34\u7523 172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007168\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e01\u0e23\u0e35\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007168 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e01\u0e23\u0e35\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01 \u0e2a\u0e01\u0e31\u0e14 \u0e40\u0e1e\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e08\u0e01 \u0e43\u0e2b\u0e49 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e44\u0e27\u0e49\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e31\u0e0d\u0e0a\u0e07 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e01\u0e31\u0e0d\u0e0a\u0e07 \u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14 \u0e22\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e22\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07 \u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e14\u0e49\u0e27\u0e22 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u8fb2\u6797\u6c34\u7523 36\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007176\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e14\u0e35 \u0e41\u0e2d\u0e25 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007176 \u0e1a\u0e08.\u0e40\u0e2d \u0e14\u0e35 \u0e41\u0e2d\u0e25 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04?\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2d\u0e31\u0e19\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 111\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0765569001488\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32 \u0e42\u0e2e\u0e21 (\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001488 \u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32 \u0e42\u0e2e\u0e21 (\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 1366\/174  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0845569010401\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e40\u0e14\u0e49\u0e19 \u0e2e\u0e34\u0e25 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010401 \u0e1a\u0e08.\u0e42\u0e01\u0e40\u0e14\u0e49\u0e19 \u0e2e\u0e34\u0e25 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 54\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569132855\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e42\u0e19\u0e0b\u0e35\u0e48 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132855 \u0e1a\u0e08.\u0e23\u0e34\u0e42\u0e19\u0e0b\u0e35\u0e48 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 (it) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 689  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e20\u0e34\u0e23\u0e31\u0e0a\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e17 \u0e40\u0e2d\u0e47\u0e21\u0e04\u0e27\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132944\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e42\u0e25\u0e42\u0e25 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132944 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e42\u0e25\u0e42\u0e25 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1901  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132952\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e1e\u0e23\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132952 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e1e\u0e23\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 554  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e01\u0e32\u0e22\u0e44\u0e19\u0e19\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 554\/43 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e22\u0e39\u0e19\u0e34\u0e15 02 \u0e16\u0e19\u0e19\u0e2d\u0e42\u0e28\u0e01-\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133029\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35\u0e17\u0e35 \u0e42\u0e2e\u0e40\u0e17\u0e25\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133029 \u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35\u0e17\u0e35 \u0e42\u0e2e\u0e40\u0e17\u0e25\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 92  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e40\u0e0b\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3571 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133100\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e32\u0e15\u0e34 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133100 \u0e1a\u0e08.\u0e2a\u0e27\u0e32\u0e15\u0e34 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32  \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 919\/513  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e40\u0e17\u0e23\u0e14 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 513a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 44 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133177\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e19\u0e40\u0e22\u0e48\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133177 \u0e1a\u0e08.\u0e04\u0e38\u0e19\u0e40\u0e22\u0e48\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e40\u0e07\u0e34\u0e19\u0e41\u0e17\u0e48\u0e07  \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 66\/50  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e22\u0e39\u0e19\u0e34\u0e15 2 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133207\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e28\u0e23\u0e35\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133207 \u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e28\u0e23\u0e35\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32,\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25,\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5efa\u8a2d 1109\/232  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133215\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e19\u0e34\u0e0b\u0e36\u0e01\u0e30 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46415\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46415\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133215 \u0e1a\u0e08.\u0e42\u0e2d\u0e19\u0e34\u0e0b\u0e36\u0e01\u0e30 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46415 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 548  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e31\u0e19 \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e22\u0e39\u0e19\u0e34\u0e15 02 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 31 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133304\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e22\u0e39\u0e19\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e41\u0e0b\u0e25 \u0e40\u0e1e\u0e47\u0e17 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133304 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e22\u0e39\u0e19\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e41\u0e0b\u0e25 \u0e40\u0e1e\u0e47\u0e17 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e22\u0e32\u0e16\u0e48\u0e32\u0e22\u0e1e\u0e22\u0e32\u0e18\u0e34\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e2a\u0e34\u0e15\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 294\/41  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002461\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e27\u0e2d\u0e0a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002461 \u0e2b\u0e08.\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e27\u0e2d\u0e0a 2569-07-14 2000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 301  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026494\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e35\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026494 \u0e1a\u0e08.\u0e18\u0e35\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 88\/318  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037177\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e1f \u0e41\u0e1a\u0e07\u0e01\u0e2d\u0e01 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037177 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e1f \u0e41\u0e1a\u0e07\u0e01\u0e2d\u0e01 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 64\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037185\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e1f \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037185 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e1f \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037193\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e1f. \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037193 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e1f. \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 173\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037240\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037240 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 82990 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 189\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037258\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e25\u0e34\u0e01\u0e39\u0e23\u0e4c \u0e1f\u0e25\u0e2d\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037258 \u0e1a\u0e08.\u0e40\u0e14\u0e25\u0e34\u0e01\u0e39\u0e23\u0e4c \u0e1f\u0e25\u0e2d\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e38\u0e14\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e16\u0e21\u0e14\u0e34\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e1f\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d \u5efa\u8a2d 88\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037304\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037304 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 37\/75  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e1a\u0e42\u0e0a\u0e04 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e1e\u0e1a\u0e42\u0e0a\u0e04 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009327\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e02\u0e21\u0e34\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009327 \u0e1a\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e02\u0e21\u0e34\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 190\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009360\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2a \u0e2d\u0e35\u0e42\u0e04\u0e48 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009360 \u0e1a\u0e08.\u0e40\u0e1a\u0e2a \u0e2d\u0e35\u0e42\u0e04\u0e48 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009378\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e17\u0e4a\u0e2d\u0e1b \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e0a\u0e49\u0e2d\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009378 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e17\u0e4a\u0e2d\u0e1b \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e0a\u0e49\u0e2d\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009386\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21. \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009386 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21. \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009394\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009394 \u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 (boi) \u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e32\u0e23\u0e19\u0e34\u0e04\u0e21-\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e01\u0e19\u0e2d.) \u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 (\u0e2a\u0e21\u0e2d.) \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19-\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 24\/90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009408\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e27\u0e35\u0e15\u0e49\u0e32 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27320\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27320\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009408 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e27\u0e35\u0e15\u0e49\u0e32 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 27320 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15  \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u0e02\u0e31\u0e49\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e0a\u0e38\u0e14\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e23\u0e27\u0e21\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30  \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e25\u0e2b\u0e30 \u88fd\u9020 501\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003817\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e31\u0e28\u0e27\u0e34\u0e19\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003817 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e31\u0e28\u0e27\u0e34\u0e19\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 99\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002012\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e1a\u0e25\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002012 \u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e1a\u0e25\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 267  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007269\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e1e\u0e25\u0e31\u0e2a \u0e1f\u0e34\u0e15\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007269 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e1e\u0e25\u0e31\u0e2a \u0e1f\u0e34\u0e15\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 31001 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u88fd\u9020 435  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0475569001502\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e04\u0e34\u0e27\u0e04\u0e34\u0e27 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001502 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e04\u0e34\u0e27\u0e04\u0e34\u0e27 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 229  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0553569000414\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e32\u0e18\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0553569000414 \u0e2b\u0e08.\u0e2a\u0e32\u0e18\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 2569-07-14 2000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e4d\u0e32\u0e16\u0e19\u0e19 \u0e40\u0e17\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e23\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32 \u0e23\u0e32\u0e07\u0e22\u0e39 \u0e23\u0e32\u0e07\u0e27\u0e35 \u0e17\u0e32\u0e07\u0e40\u0e1a\u0e35\u0e48\u0e22\u0e07\u0e19\u0e4d\u0e49\u0e32 \u0e17\u0e32\u0e07\u0e19\u0e4d\u0e49\u0e32\u0e44\u0e2b\u0e25 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 269  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0655569002256\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e40\u0e1e\u0e47\u0e17 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002256 \u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e40\u0e1e\u0e47\u0e17 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 258\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0735569007087\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e1f \u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e01 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007087 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e1f \u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e01 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0775569002981\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e25\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e1f\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002981 \u0e1a\u0e08.\u0e0b\u0e2d\u0e25\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e1f\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 38\/126  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569013027\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2b\u0e25\u0e07 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013027 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2b\u0e25\u0e07 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 23\/526  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010371\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e2a\u0e21\u0e38\u0e22 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010371 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e2a\u0e21\u0e38\u0e22 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 (\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 131\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0855569000545\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000545 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 2000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0943569000259\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e17\u0e35 \u0e2d\u0e31\u0e25\u0e21\u0e32\u0e2a 1447\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0943569000259 \u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e17\u0e35 \u0e2d\u0e31\u0e25\u0e21\u0e32\u0e2a 1447 2569-07-14 2000000 47113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569132197\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2b\u0e25\u0e34\u0e19 \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132197 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2b\u0e25\u0e34\u0e19 \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 46632 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01  \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e34\u0e14\u0e1c\u0e34\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1c\u0e19\u0e31\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1d\u0e49\u0e32\u0e40\u0e1e\u0e14\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e27\u0e07\u0e01\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19  \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e22\u0e32\u0e07 spc \u0e44\u0e21\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e25\u0e32\u0e21\u0e34\u0e40\u0e19\u0e15 \u0e44\u0e21\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e1e\u0e37\u0e49\u0e19\u0e44\u0e21\u0e49\u0e40\u0e17\u0e35\u0e22\u0e21 wpc \u0e41\u0e1c\u0e48\u0e19\u0e1c\u0e19\u0e31\u0e07 wpc \u0e41\u0e1c\u0e48\u0e19\u0e1d\u0e49\u0e32 upvc \u0e1c\u0e19\u0e31\u0e07\u0e2b\u0e34\u0e19\u0e40\u0e17\u0e35\u0e22\u0e21 pu \u0e1b\u0e23\u0e30\u0e15\u0e39 upvc  \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e44\u0e21\u0e49 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e44\u0e21\u0e49\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e21\u0e25\u0e32\u0e21\u0e35\u0e19 \u0e27\u0e07\u0e01\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e44\u0e21\u0e49 \u0e27\u0e07\u0e01\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39 wpc \u0e27\u0e07\u0e01\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39 pvc \u0e44\u0e21\u0e49\u0e04\u0e34\u0e49\u0e27 \u0e44\u0e21\u0e49\u0e1a\u0e31\u0e27 \u0e04\u0e34\u0e49\u0e27 \u0e1a\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e49\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01 \u0e44\u0e21\u0e49\u0e08\u0e23\u0e34\u0e07 pvc \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e1e\u0e25\u0e35\u0e22\u0e39\u0e23\u0e35\u0e40\u0e17\u0e19 \u0e44\u0e21\u0e49\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e23\u0e32\u0e27\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e25\u0e39\u0e01\u0e01\u0e23\u0e07\u0e44\u0e21\u0e49 \u0e23\u0e32\u0e27\u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19\u0e44\u0e21\u0e49 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e42\u0e1f\u0e21 pe \u0e42\u0e1f\u0e21 ixpe \u0e01\u0e32\u0e27 \u0e0b\u0e35\u0e25\u0e41\u0e25\u0e19\u0e17\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 776  \u0e0b\u0e2d\u0e22 \u0e44\u0e2a\u0e27\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132367\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e19\u0e14\u0e49\u0e32 \u0e44\u0e2d\u0e42\u0e2d\u0e17\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132367 \u0e1a\u0e08.\u0e41\u0e1e\u0e19\u0e14\u0e49\u0e32 \u0e44\u0e2d\u0e42\u0e2d\u0e17\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 70209 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e3523 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1723(\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132383\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132383 \u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (it) \u0e01\u0e32\u0e23\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 898\/31-32  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1903 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132421\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e1e\u0e35\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132421 \u0e1a\u0e08.\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e1e\u0e35\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21\u0e2d\u0e1a \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1e\u0e2a\u0e17\u0e23\u0e35 (pastry) \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e49\u0e01 \u0e04\u0e38\u0e4a\u0e01\u0e01\u0e35\u0e49 \u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 71\/14  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132499\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132499 \u0e1a\u0e08.\u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 711  \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 64 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132529\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132529 \u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 10751 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e34\u0e0b\u0e0b\u0e48\u0e32 \u0e2a\u0e1b\u0e32\u0e40\u0e01\u0e47\u0e15\u0e15\u0e35\u0e49 \u0e25\u0e32\u0e0b\u0e31\u0e19\u0e22\u0e48\u0e32 \u0e2f\u0e25\u0e2f \u88fd\u9020 1673\/312  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132596\",\"name_th\":\"\u0e1a\u0e08. \u0e19\u0e32\u0e19\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132596 \u0e1a\u0e08. \u0e19\u0e32\u0e19\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 85\/1406  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 79 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132626\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e17 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132626 \u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e17 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 107  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e14\u0e2d\u0e07\u0e01\u0e34 \u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 404 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023193\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49 \u0e1a\u0e25\u0e39\u0e21 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023193 \u0e1a\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49 \u0e1a\u0e25\u0e39\u0e21 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 400  \u0e16\u0e19\u0e19\u0e28\u0e34\u0e23\u0e34\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026257\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e27\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026257 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e27\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026320\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1e\u0e25\u0e35\u0e01\u0e2d\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22230\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22230\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026320 \u0e1a\u0e08.\u0e42\u0e1e\u0e25\u0e35\u0e01\u0e2d\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 22230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e17\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 (\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e41\u0e04\u0e23\u0e47\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e27\u0e31\u0e15\u0e16\u0e38\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e15\u0e31\u0e49\u0e07\u0e15\u0e49\u0e19) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e48\u0e2d\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c hvac \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e31\u0e19\u0e0b\u0e36\u0e21 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e34\u0e28\u0e27 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e31\u0e19\u0e19\u0e49\u0e33 \u88fd\u9020 5\/1  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 27 \u0e41\u0e22\u0e01 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002402\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e44\u0e15\u0e25\u0e4c 2026\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002402 \u0e2b\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e44\u0e15\u0e25\u0e4c 2026 2569-07-13 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15  \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/653  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002429\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e1e\u0e35\u0e04 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002429 \u0e2b\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e1e\u0e35\u0e04 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-13 2000000 10751 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19\u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u88fd\u9020 45\/268  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002437\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e21\u0e14 \u0e04\u0e25\u0e2d\u0e40\u0e0b\u0e47\u0e17\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002437 \u0e2b\u0e08.\u0e42\u0e21\u0e14 \u0e04\u0e25\u0e2d\u0e40\u0e0b\u0e47\u0e17 2569-07-13 2000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15  \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/653  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569036863\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036863 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 168\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036901\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036901 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e49\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u88fd\u9020 44\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036944\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e08\u0e34\u0e1b\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036944 \u0e1a\u0e08.\u0e23\u0e38\u0e08\u0e34\u0e1b\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037061\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e14\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037061 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e14\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 27101 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u88fd\u9020 7\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037070\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037070 \u0e1a\u0e08.\u0e41\u0e21\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e15\u0e31\u0e27\u0e40\u0e40\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 8\/105   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 201 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037096\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e32 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037096 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e32 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 300\/47-48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009301\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e22\u0e27\u0e19\u0e15\u0e49\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009301 \u0e1a\u0e08.\u0e2b\u0e22\u0e27\u0e19\u0e15\u0e49\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d byd \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 161\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0255569002004\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002004 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e1b\u0e39\u0e42\u0e15\u0e4a\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 845\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007251\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08.\u0e42\u0e2d.\u0e27\u0e32\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007251 \u0e1a\u0e08.\u0e40\u0e08.\u0e42\u0e2d.\u0e27\u0e32\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/5  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e15 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0365569001431\",\"name_th\":\"\u0e1a\u0e08. \u0e01\u0e39\u0e49\u0e14\u0e44\u0e27\u0e1a\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001431 \u0e1a\u0e08. \u0e01\u0e39\u0e49\u0e14\u0e44\u0e27\u0e1a\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u533b\u7642\u30fb\u798f\u7949 115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0405569006725\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006725 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006733\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006733 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015839\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e42\u0e27 \u0e25\u0e31\u0e01\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015839 \u0e1a\u0e08.\u0e1f\u0e32\u0e42\u0e27 \u0e25\u0e31\u0e01\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e17\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 257\/7  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0603569001584\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e08\u0e34\u0e07 \u0e27\u0e31\u0e19 \u0e0a\u0e4a\u0e2d\u0e1b\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001584 \u0e2b\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e08\u0e34\u0e07 \u0e27\u0e31\u0e19 \u0e0a\u0e4a\u0e2d\u0e1b 2569-07-13 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23  \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 (\u0e17\u0e49\u0e07\u0e21\u0e37\u0e2d1 \u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d2) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001592\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e42\u0e2d\u0e40\u0e04 \u0e21\u0e34\u0e19\u0e34 \u0e0a\u0e4a\u0e2d\u0e1b\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001592 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e42\u0e2d\u0e40\u0e04 \u0e21\u0e34\u0e19\u0e34 \u0e0a\u0e4a\u0e2d\u0e1b 2569-07-13 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0623569000731\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2026\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000731 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2026 2569-07-13 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 258\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0625569000776\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e22\u0e28 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 3993 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000776 \u0e1a\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e22\u0e28 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 3993 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 341\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0635569001446\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e19 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001446 \u0e1a\u0e08.\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e19 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 897\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e48\u0e27\u0e21\u0e43\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0723569000668\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e17\u0e1e\u0e17\u0e2d\u0e07 \u0e19\u0e34\u0e27 \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000668 \u0e2b\u0e08.\u0e40\u0e17\u0e1e\u0e17\u0e2d\u0e07 \u0e19\u0e34\u0e27 \u0e0a\u0e47\u0e2d\u0e1b 2569-07-13 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01  \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001036\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52101\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52101\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001036 \u0e2b\u0e08.\u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-13 2000000 52101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007320\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e32\u0e17\u0e4c\u0e44\u0e27\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007320 \u0e1a\u0e08.\u0e40\u0e2d\u0e32\u0e17\u0e4c\u0e44\u0e27\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 219\/154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569012918\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e22\u0e32 \u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012918 \u0e1a\u0e08.\u0e0b\u0e32\u0e22\u0e32 \u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 96101 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e15 \u0e23\u0e48\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e01\u0e14 \u0e01\u0e32\u0e23\u0e04\u0e25\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e35\u0e1a \u0e01\u0e32\u0e23\u0e14\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e04\u0e1a \u0e01\u0e32\u0e23\u0e2d\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e15\u0e32\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 18\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012926\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35 \u0e44\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012926 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35 \u0e44\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21 \u0e44\u0e1b\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 77\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0843569001337\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e49\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e08\u0e34\u0e23\u0e32\u0e1e\u0e23 \u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001337 \u0e2b\u0e08.\u0e2b\u0e49\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e08\u0e34\u0e23\u0e32\u0e1e\u0e23 \u0e19\u0e04\u0e23\u0e28\u0e23\u0e35 2569-07-13 2000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569009297\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e48\u0e07\u0e17\u0e31\u0e48\u0e27 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009297 \u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e48\u0e07\u0e17\u0e31\u0e48\u0e27 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 2000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7777\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0813569000446\",\"name_th\":\"\u0e2b\u0e08.\u0e1b. \u0e1b\u0e25\u0e32 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0813569000446 \u0e2b\u0e08.\u0e1b. \u0e1b\u0e25\u0e32 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 2569-07-12 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 281\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569012896\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e0a\u0e32\u0e23\u0e08\u0e4c\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47895\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47895\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012896 \u0e1a\u0e08.\u0e23\u0e35\u0e0a\u0e32\u0e23\u0e08\u0e4c\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 2000000 47895 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e22\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0125569026222\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026222 \u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 2000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e2a\u0e1b\u0e32\u0e1c\u0e21 \u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e17\u0e33\u0e2a\u0e35\u0e1c\u0e21 \u0e08\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e17\u0e23\u0e07\u0e1c\u0e21 \u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e14\u0e39\u0e41\u0e25\u0e40\u0e25\u0e47\u0e1a \u0e19\u0e27\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e2a\u0e1b\u0e32\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e25\u0e47\u0e1a\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 116  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0143569001180\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e08\u0e35 \u0e40\u0e1f\u0e23\u0e0a \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001180 \u0e2b\u0e08.\u0e27\u0e35\u0e08\u0e35 \u0e40\u0e1f\u0e23\u0e0a \u0e0a\u0e47\u0e2d\u0e1b 2569-07-11 2000000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01  \u0e1b\u0e25\u0e32\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 (\u0e40\u0e0a\u0e48\u0e19\u0e1b\u0e25\u0e32\u0e0a\u0e48\u0e2d\u0e19 \u0e1b\u0e25\u0e32\u0e19\u0e34\u0e25 \u0e1b\u0e25\u0e32\u0e14\u0e38\u0e01 \u0e1b\u0e25\u0e32\u0e17\u0e31\u0e21\u0e17\u0e34\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e1b\u0e25\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14)   \u0e15\u0e32\u0e21\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e40\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0203569002991\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19 17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e4c\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002991 \u0e2b\u0e08.\u0e17\u0e35 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19 17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e4c 2569-07-11 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 369  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036839\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e22\u0e47\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96109\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96109\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036839 \u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e22\u0e47\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 2000000 96109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e32\u0e18\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32 (harvia \u0e41\u0e25\u0e30 diooist \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 tuv) \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 300\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036847\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036847 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 174\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0605569001993\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e22\u0e0b\u0e38\u0e49\u0e22 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 1957 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001993 \u0e1a\u0e08.\u0e19\u0e32\u0e22\u0e0b\u0e38\u0e49\u0e22 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 1957 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e02\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 39\/3  \u0e16\u0e19\u0e19\u0e2d\u0e23\u0e23\u0e16\u0e01\u0e27\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002019\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002019 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 2000000 46414 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0745569007273\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e2d\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33190\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33190\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007273 \u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e2d\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 2000000 33190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25,\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b,\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e02\u0e49\u0e2d\u0e1a\u0e01\u0e1e\u0e23\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29: \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e34\u0e1f\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e22\u0e01 \u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e23\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21:\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e41\u0e1b\u0e25\u0e07\u0e04\u0e27\u0e32\u0e21\u0e16\u0e35\u0e48 plc \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19:\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2a\u0e27\u0e34\u0e15\u0e0a\u0e4c\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e15\u0e48\u0e33 \u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\/\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e44\u0e1f \u88fd\u9020 115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569130917\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35.\u0e44\u0e2d.\u0e27\u0e35.\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46431\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46431\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130917 \u0e1a\u0e08.\u0e27\u0e35.\u0e44\u0e2d.\u0e27\u0e35.\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 46431 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 335\/63  \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e41\u0e25\u0e19\u0e14\u0e4c1 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130950\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e01\u0e49\u0e32\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130950 \u0e1a\u0e08.\u0e40\u0e27\u0e01\u0e49\u0e32\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 68101 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 4454  \u0e2d\u0e32\u0e04\u0e32\u0e23aspire \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1075 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 32 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131115\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43110\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43110\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131115 \u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 43110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c(solarrooftop, solar \u5efa\u8a2d 51\/75  \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131247\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e48\u0e2a\u0e15\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131247 \u0e1a\u0e08.\u0e44\u0e2e\u0e48\u0e2a\u0e15\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (shipping) \u904b\u8f38\u30fb\u7269\u6d41 719  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s07 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 23 \u0e42\u0e0b\u0e19 c \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131344\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131344 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e01\u0e14\u0e08\u0e38\u0e14 \u0e22\u0e37\u0e14\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e27\u0e14\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22 \u0e19\u0e27\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e32\u0e1e\u0e35  \u0e2a\u0e1b\u0e32\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 50\/2  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131417\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e23\u0e39\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131417 \u0e1a\u0e08.\u0e1f\u0e23\u0e39\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32-\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e2b\u0e49\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/12  \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131450\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e17 \u0e44\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131450 \u0e1a\u0e08.\u0e41\u0e21\u0e17 \u0e44\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e17\u0e33 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e25\u0e17\u0e4c\u0e2d\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131638\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2a\u0e27\u0e35\u0e17 \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131638 \u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2a\u0e27\u0e35\u0e17 \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 35  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 58 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569021395\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e35 \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021395 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e35 \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 29\/68  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2a\u0e19\u0e32\u0e01\u0e23\u0e35\u0e19\u0e27\u0e34\u0e25\u0e25\u0e4c (\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32\u0e04\u0e25\u0e2d\u0e07 2) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569036553\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e44\u0e17\u0e22 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036553 \u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e44\u0e17\u0e22 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e34\u0e48\u0e21 (vat) \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\/\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 65\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036634\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e44\u0e17\u0e48 \u0e40\u0e0a\u0e34\u0e48\u0e07\u0e15\u0e4b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46594\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46594\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036634 \u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e44\u0e17\u0e48 \u0e40\u0e0a\u0e34\u0e48\u0e07\u0e15\u0e4b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 46594 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 276\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036693\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e07\u0e2b\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036693 \u0e1a\u0e08.\u0e21\u0e34\u0e07\u0e2b\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 68201 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e31\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e14\u0e39\u0e41\u0e25  \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23  \u0e14\u0e39\u0e41\u0e25\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u4e0d\u52d5\u7523 678\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036782\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e48 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036782 \u0e1a\u0e08.\u0e0b\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e48 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e04\u0e48\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009220\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e1a\u0e2d\u0e22\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009220 \u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e1a\u0e2d\u0e22\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 44\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009246\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e39\u0e23\u0e1e\u0e32 64 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009246 \u0e1a\u0e08.\u0e1a\u0e39\u0e23\u0e1e\u0e32 64 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 78109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19 \u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 112\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003744\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19\u0e01\u0e23\u0e38\u0e4a\u0e1b 1 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003744 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19\u0e01\u0e23\u0e38\u0e4a\u0e1b 1 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 255  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569007188\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47214\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47214\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007188 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 47214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 270  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0405569006601\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e22\u0e40\u0e27\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006601 \u0e1a\u0e08.\u0e42\u0e22\u0e40\u0e27\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 47712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 (franchise) \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/3   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006610\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e25\u0e39\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006610 \u0e1a\u0e08.\u0e2e\u0e32\u0e25\u0e39\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e25\u0e47\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/3   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0443569000776\",\"name_th\":\"\u0e2b\u0e08. \u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08 \u0e41\u0e2d\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000776 \u0e2b\u0e08. \u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08 \u0e41\u0e2d\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 2569-07-10 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01 \u0e2b\u0e19\u0e2d\u0e07 \u0e04\u0e25\u0e2d\u0e07 \u0e1a\u0e36\u0e07 \u5efa\u8a2d 115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0505569015600\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2e\u0e32\u0e1b\u0e1b\u0e35\u0e49\u0e40\u0e19\u0e2a 95 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015600 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2e\u0e32\u0e1b\u0e1b\u0e35\u0e49\u0e40\u0e19\u0e2a 95 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 63113 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-marketplace) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e02\u0e32\u0e22\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e19\u0e33\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e21\u0e32\u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e42\u0e06\u0e29\u0e13\u0e32 \u60c5\u5831\u901a\u4fe1\u30fbit 405\/70  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015677\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e0a\u0e31\u0e22 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015677 \u0e1a\u0e08.\u0e21\u0e35\u0e0a\u0e31\u0e22 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0775569002956\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e34\u0e22\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1f\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002956 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e34\u0e22\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1f\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e14\u0e49\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e01\u0e49\u0e2d\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e0d\u0e0a\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 4\/104  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e41\u0e01 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0803569000942\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e23\u0e35\u0e27\u0e31\u0e19\u0e1e\u0e37\u0e0a\u0e1c\u0e25 2026\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000942 \u0e2b\u0e08.\u0e28\u0e23\u0e35\u0e27\u0e31\u0e19\u0e1e\u0e37\u0e0a\u0e1c\u0e25 2026 2569-07-10 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2b\u0e2d\u0e21\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e21\u0e30\u0e02\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e0b\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e1e\u0e23\u0e30 \u0e16\u0e19\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002645\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e35\u0e01\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002645 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e35\u0e01\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 1626  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002653\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08.\u0e40\u0e2d\u0e2a.27 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e04\u0e04\u0e32\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002653 \u0e1a\u0e08.\u0e40\u0e08.\u0e40\u0e2d\u0e2a.27 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e04\u0e04\u0e32\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 1127\/3  \u0e16\u0e19\u0e19\u0e21\u0e40\u0e2b\u0e22\u0e07\u0e13\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569012845\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e0b\u0e32\u0e27\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012845 \u0e1a\u0e08.\u0e27\u0e34\u0e0b\u0e32\u0e27\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 108\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012861\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e1f\u0e34\u0e01\u0e0b\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012861 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e1f\u0e34\u0e01\u0e0b\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 41001 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a \u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u5efa\u8a2d 271\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010222\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e41\u0e1e\u0e04 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010222 \u0e1a\u0e08.\u0e42\u0e0a\u0e41\u0e1e\u0e04 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 57\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1e\u0e48\u0e2d\u0e02\u0e38\u0e19\u0e17\u0e30\u0e40\u0e25 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010281\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e42\u0e04 \u0e42\u0e1b\u0e42\u0e25 \u0e1a\u0e32\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010281 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e42\u0e04 \u0e42\u0e1b\u0e42\u0e25 \u0e1a\u0e32\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e23\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 202\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010290\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e2a\u0e1b\u0e34\u0e23\u0e34\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47221\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47221\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010290 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e2a\u0e1b\u0e34\u0e23\u0e34\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 47221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 151\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010303\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49 \u0e2d\u0e35\u0e40\u0e25\u0e1f\u0e40\u0e1f\u0e48\u0e19 \u0e42\u0e2e\u0e21\u0e2a\u0e4c \u0e1a\u0e32\u0e22 \u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010303 \u0e1a\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49 \u0e2d\u0e35\u0e40\u0e25\u0e1f\u0e40\u0e1f\u0e48\u0e19 \u0e42\u0e2e\u0e21\u0e2a\u0e4c \u0e1a\u0e32\u0e22 \u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e40\u0e01\u0e2a\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e42\u0e2e\u0e25\u0e40\u0e17\u0e25 \u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u5bbf\u6cca\u30fb\u98f2\u98df 54\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569129749\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e04\u0e27\u0e40\u0e2d\u0e47\u0e15 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129749 \u0e1a\u0e08.\u0e44\u0e04\u0e27\u0e40\u0e2d\u0e47\u0e15 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 475   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 202 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 75 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129951\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129951 \u0e1a\u0e08.\u0e40\u0e21\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1a\u0e19\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 159\/37  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e21\u0e34\u0e15\u0e23\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2301 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 23 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 21 (\u0e2d\u0e42\u0e28\u0e01) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130011\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e19\u0e32\u0e04\u0e32 \u0e2a\u0e31\u0e1b\u0e1b\u0e32\u0e22\u0e30 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e0b\u0e07\u0e0a\u0e31\u0e27\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130011 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e19\u0e32\u0e04\u0e32 \u0e2a\u0e31\u0e1b\u0e1b\u0e32\u0e22\u0e30 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e0b\u0e07\u0e0a\u0e31\u0e27\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e31\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130151\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e01\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130151 \u0e1a\u0e08.\u0e42\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e01\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 140  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e31\u0e19 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e40\u0e1e\u0e25\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1705 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130194\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e1f \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130194 \u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e1f \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e19\u0e21\u0e16\u0e31\u0e48\u0e27\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e19\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e31\u0e0a\u0e15\u0e4c\u0e20\u0e32\u0e04\u0e22\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 21 (\u0e2d\u0e42\u0e28\u0e01) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130381\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e44\u0e1f\u0e19\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130381 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e44\u0e1f\u0e19\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (inbound tour) \u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15: \u0e19\u0e33\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e21\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 192\/63  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0739(\u0e40\u0e17\u0e1e\u0e25\u0e35\u0e25\u0e321) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130615\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e40\u0e27\u0e19\u0e34\u0e27 \u0e2d\u0e2d\u0e1f \u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130615 \u0e1a\u0e08.\u0e2d\u0e40\u0e27\u0e19\u0e34\u0e27 \u0e2d\u0e2d\u0e1f \u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 600\/63  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 39 (\u0e40\u0e17\u0e1e\u0e25\u0e35\u0e25\u0e32 1) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130721\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32-\u0e23\u0e38\u0e48\u0e07 \u0e27\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130721 \u0e1a\u0e08.\u0e1f\u0e32-\u0e23\u0e38\u0e48\u0e07 \u0e27\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e2d\u0e25\u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e1c\u0e19\u0e31\u0e07 \u0e27\u0e2d\u0e25\u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e21\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e40\u0e23\u0e47\u0e27 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/562  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e34\u0e15\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130780\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e2a\u0e25\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130780 \u0e1a\u0e08.\u0e42\u0e23\u0e2a\u0e25\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/9  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e40\u0e27\u0e2c\u0e38\u0e27\u0e19\u0e32\u0e23\u0e32\u0e21 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130798\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e0b\u0e14 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130798 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e0b\u0e14 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 10\/5  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e17\u0e23\u0e19\u0e14\u0e35\u0e49 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 g \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 13 (\u0e41\u0e2a\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002330\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e04\u0e32\u0e23\u0e4c \u0e27\u0e2d\u0e0a\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002330 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e04\u0e32\u0e23\u0e4c \u0e27\u0e2d\u0e0a 2569-07-09 2000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u0e25\u0e49\u0e32\u0e07\u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e14\u0e39\u0e14\u0e1d\u0e38\u0e48\u0e19 \u0e0b\u0e31\u0e01\u0e40\u0e1a\u0e32\u0e30 \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21 \u0e02\u0e31\u0e14\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27  \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022855\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e39\u0e40\u0e19\u0e48 \u0e2a\u0e44\u0e15\u0e25\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022855 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e39\u0e40\u0e19\u0e48 \u0e2a\u0e44\u0e15\u0e25\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022863\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022863 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022901\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e42\u0e21\u0e40\u0e14\u0e2d \u0e41\u0e1f\u0e25\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022901 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e42\u0e21\u0e40\u0e14\u0e2d \u0e41\u0e1f\u0e25\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022928\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022928 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 60\/121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569021158\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021158 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 234\/200  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021204\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e27\u0e34\u0e48\u0e19\u0e2d\u0e35\u0e49 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021204 \u0e1a\u0e08.\u0e22\u0e27\u0e34\u0e48\u0e19\u0e2d\u0e35\u0e49 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u904b\u8f38\u30fb\u7269\u6d41 71\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021212\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e27\u0e1f \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021212 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e27\u0e1f \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 11\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021255\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e39\u0e2a\u0e40\u0e17\u0e25 \u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021255 \u0e1a\u0e08.\u0e1a\u0e39\u0e2a\u0e40\u0e17\u0e25 \u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u5efa\u8a2d 137\/77-78  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021298\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e21 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021298 \u0e1a\u0e08.\u0e42\u0e23\u0e21 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e02\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 11\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0195569002501\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e02\u0e14\u0e35 \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002501 \u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e02\u0e14\u0e35 \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 466\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036260\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e14 \u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036260 \u0e1a\u0e08.\u0e40\u0e23\u0e14 \u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07 \u0e23\u0e16\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e32 \u0e23\u0e16\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e02\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 189\/161  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 9 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e1a\u0e38\u0e0d\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036286\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35.\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e04\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036286 \u0e1a\u0e08.\u0e27\u0e35.\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e04\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e4d\u0e32\u0e19\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e4d\u0e32\u0e19\u0e4d\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e4d\u0e32\u0e2b\u0e19\u0e14 \u4e0d\u52d5\u7523 353\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036359\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e25\u0e25\u0e34\u0e41\u0e01\u0e19\u0e17\u0e4c \u0e40\u0e01\u0e23\u0e0b \u0e2d\u0e25\u0e39 \u0e1a\u0e34\u0e49\u0e27\u0e17\u0e4c\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31002\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31002\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036359 \u0e1a\u0e08.\u0e40\u0e2d\u0e25\u0e25\u0e34\u0e41\u0e01\u0e19\u0e17\u0e4c \u0e40\u0e01\u0e23\u0e0b \u0e2d\u0e25\u0e39 \u0e1a\u0e34\u0e49\u0e27\u0e17\u0e4c\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 31002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e07\u0e32\u0e19\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036367\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e27\u0e48\u0e19 \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17020\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17020\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036367 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e27\u0e48\u0e19 \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 17020 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e17\u0e1b\u0e01\u0e32\u0e27 \u0e40\u0e17\u0e1b\u0e01\u0e32\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07  \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u88fd\u9020 888\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036375\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19 \u0e08\u0e35 \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036375 \u0e1a\u0e08.\u0e08\u0e34\u0e19 \u0e08\u0e35 \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 1\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036499\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e15 \u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036499 \u0e1a\u0e08.\u0e21\u0e35\u0e15 \u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036511\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e2a\u0e15\u0e34\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036511 \u0e1a\u0e08.\u0e2d\u0e2d\u0e2a\u0e15\u0e34\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 7\/30,7\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009149\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009149 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 102\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009190\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e0a\u0e23\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009190 \u0e1a\u0e08.\u0e1e\u0e31\u0e0a\u0e23\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e2d\u0e01\u0e0a\u0e19(\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u5efa\u8a2d 65  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0345569003158\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003158 \u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 388\/75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0403569003058\",\"name_th\":\"\u0e2b\u0e08. \u0e40\u0e0a\u0e47\u0e04\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e42\u0e21\u0e42\u0e15\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003058 \u0e2b\u0e08. \u0e40\u0e0a\u0e47\u0e04\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e42\u0e21\u0e42\u0e15\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-09 2000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e23\u0e16 \u0e23\u0e16\u0e27\u0e34\u0e1a\u0e32\u0e01 \u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e15\u0e4c\u0e27\u0e34\u0e1a\u0e32\u0e01 \u82b8\u8853\u30fb\u5a2f\u697d 225  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006555\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e17\u0e19\u0e01\u0e31\u0e1a\u0e21\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006555 \u0e1a\u0e08.\u0e41\u0e17\u0e19\u0e01\u0e31\u0e1a\u0e21\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e4d\u0e49\u0e32\u0e21\u0e31\u0e19 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001472\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001472 \u0e1a\u0e08.\u0e44\u0e2e\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001481\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e2b\u0e22\u0e27\u0e19\u0e2b\u0e22\u0e32\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001481 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e2b\u0e22\u0e27\u0e19\u0e2b\u0e22\u0e32\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 271  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015529\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015529 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 382\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0535569000734\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e42\u0e04\u0e27\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000734 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e42\u0e04\u0e27\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 150\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0745569007206\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e1e\u0e32\u0e23\u0e4c\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007206 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e1e\u0e32\u0e23\u0e4c\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 29309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e2d\u0e23\u0e4c \u88fd\u9020 9\/79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0825569001126\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2b\u0e21 \u0e40\u0e04\u0e23\u0e2a\u0e15\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001126 \u0e1a\u0e08.\u0e44\u0e2b\u0e21 \u0e40\u0e04\u0e23\u0e2a\u0e15\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 big bike \u0e41\u0e25\u0e30 \u0e23\u0e16 harley-davidson \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569012713\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e1e\u0e32\u0e13\u0e34\u0e0a \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47111\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47111\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012713 \u0e1a\u0e08.\u0e2a\u0e32\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e1e\u0e32\u0e13\u0e34\u0e0a \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 47111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45-47  \u0e16\u0e19\u0e19\u0e23\u0e30\u0e19\u0e2d\u0e07 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012721\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e2b\u0e4c\u0e2d\u0e34\u0e19\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\u0e2a \u0e41\u0e01\u0e25\u0e25\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012721 \u0e1a\u0e08.\u0e42\u0e04\u0e2b\u0e4c\u0e2d\u0e34\u0e19\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\u0e2a \u0e41\u0e01\u0e25\u0e25\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 206\/7-8  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0f\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 200 \u0e1b\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010176\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e2d\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2d\u0e4a\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010176 \u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e2d\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2d\u0e4a\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e17\u0e33\u0e1c\u0e21 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e17\u0e23\u0e07\u0e1c\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 147\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010184\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010184 \u0e1a\u0e08.\u0e17\u0e35 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 73\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010206\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e39\u0e21\u0e35\u0e19\u0e48\u0e32 \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010206 \u0e1a\u0e08.\u0e19\u0e39\u0e21\u0e35\u0e19\u0e48\u0e32 \u0e40\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 69\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569128718\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e23\u0e34\u0e42\u0e14\u0e25\u0e25\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128718 \u0e1a\u0e08.\u0e42\u0e17\u0e23\u0e34\u0e42\u0e14\u0e25\u0e25\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e48\u0e2d\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e01\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u91d1\u878d\u30fb\u4fdd\u967a 2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e2a\u0e21\u0e34\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23 (\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128882\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e42\u0e0a \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128882 \u0e1a\u0e08.\u0e27\u0e32\u0e42\u0e0a \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24  \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128939\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e0a\u0e27\u0e19\u0e40\u0e0a\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128939 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e0a\u0e27\u0e19\u0e40\u0e0a\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e2b\u0e21\u0e27\u0e01  \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e23\u0e38\u0e29\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 340\/5  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2787 (\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129099\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e0b\u0e35\u0e48 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129099 \u0e1a\u0e08.\u0e40\u0e25\u0e0b\u0e35\u0e48 \u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 (\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c) \u0e42\u0e23\u0e07\u0e22\u0e34\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e04\u0e25\u0e31\u0e1a \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e42\u0e22\u0e04\u0e30 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e25\u0e32\u0e17\u0e34\u0e2a \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 973  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e23\u0e2a\u0e34\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2d\u0e32\u0e40\u0e02\u0e15 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e23\u0e2a\u0e34\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e1a\u0e3503, \u0e1a\u0e3516 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2a\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129129\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e42\u0e01\u0e23\u0e27\u0e4c \u0e2d\u0e35-\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129129 \u0e1a\u0e08.\u0e27\u0e35\u0e42\u0e01\u0e23\u0e27\u0e4c \u0e2d\u0e35-\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d e-commerce) (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21 \u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e08\u0e39\u0e23\u0e35\u0e48 \u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e39\u0e1f\u0e27\u0e35\u0e48 \u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s-05 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129196\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129196 \u0e1a\u0e08.\u0e44\u0e14\u0e49\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e32\u0e23\u0e4c (\u0e44\u0e19\u0e17\u0e4c \u0e04\u0e25\u0e31\u0e1a) \u5bbf\u6cca\u30fb\u98f2\u98df 184  \u0e0b\u0e2d\u0e22 67 \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129226\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e42\u0e1f\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129226 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e42\u0e1f\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 456\/351  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 45 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129277\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e04\u0e34\u0e07\u0e2a\u0e4c \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e4a\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e17\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129277 \u0e1a\u0e08.\u0e40\u0e04 \u0e04\u0e34\u0e07\u0e2a\u0e4c \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e4a\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e17\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/4  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129285\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e21\u0e30 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129285 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e21\u0e30 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e2a\u0e21\u0e34\u0e19 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23 (\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129307\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e15\u0e4c \u0e04\u0e34\u0e27\u0e15\u0e4c \u0e41\u0e04\u0e19\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129307 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e15\u0e4c \u0e04\u0e34\u0e27\u0e15\u0e4c \u0e41\u0e04\u0e19\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/86  \u0e0b\u0e2d\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129315\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35 18 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129315 \u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35 18 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 395\/418  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129366\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e14\u0e4c\u0e44\u0e1a\u0e17\u0e2a\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129366 \u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e14\u0e4c\u0e44\u0e1a\u0e17\u0e2a\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 1000\/39  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 55 (\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129391\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e4a\u0e1a\u0e1b\u0e35\u0e49 \u0e01\u0e23\u0e39\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129391 \u0e1a\u0e08.\u0e1b\u0e31\u0e4a\u0e1a\u0e1b\u0e35\u0e49 \u0e01\u0e23\u0e39\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 67\/37  \u0e16\u0e19\u0e19\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022545\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e04 \u0e40\u0e27\u0e25 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022545 \u0e1a\u0e08.\u0e40\u0e21\u0e04 \u0e40\u0e27\u0e25 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47190 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e07\u0e32\u0e19, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 176\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022618\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e0b\u0e31\u0e19\u0e25\u0e34\u0e15 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e1f\u0e39 \u0e25\u0e39\u0e0b\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022618 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e0b\u0e31\u0e19\u0e25\u0e34\u0e15 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e1f\u0e39 \u0e25\u0e39\u0e0b\u0e35\u0e48\u0e2b\u0e25\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/110   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a104 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022634\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e2d\u0e35\u0e27\u0e35 \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e08\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022634 \u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e2d\u0e35\u0e27\u0e35 \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e08\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 258\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022677\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022677 \u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07  \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025595\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e17\u0e4c\u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025595 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e17\u0e4c\u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e25\u0e49\u0e32\u0e07 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/453  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e42\u0e2e\u0e21\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020976\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e01\u0e34\u0e27 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020976 \u0e1a\u0e08.\u0e27\u0e32\u0e01\u0e34\u0e27 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47712 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 80\/26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569035930\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e19\u0e18\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035930 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e19\u0e18\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e22\u0e01\u0e40\u0e25\u0e34\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e2d\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e2d\u0e01\u0e43\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19\u0e42\u0e09\u0e19\u0e14\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e43\u0e19\u0e42\u0e09\u0e19\u0e14\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u4e0d\u52d5\u7523 171\/152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035972\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e22\u0e48\u0e07\u0e40\u0e09\u0e34\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035972 \u0e1a\u0e08.\u0e2b\u0e22\u0e48\u0e07\u0e40\u0e09\u0e34\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e08\u0e32\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e4a\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e15\u0e31\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e21\u0e48 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e2a\u0e07\u0e40\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e04\u0e25\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e42\u0e0b\u0e19\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e21\u0e32\u0e2d\u0e32\u0e23\u0e4c\u0e01 \u0e41\u0e21\u0e01\u0e40\u0e19\u0e15\u0e34\u0e01\u0e1e\u0e25\u0e31\u0e2a \u0e2f\u0e25\u0e2f \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e01 \u0e23\u0e16\u0e22\u0e01 \u0e40\u0e2e\u0e35\u0e49\u0e22\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e42\u0e17\u0e23\u0e19\u0e34\u0e04 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e14\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/31  \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35-\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e36\u0e07 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035999\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e19\u0e14\u0e2d\u0e19\u0e44\u0e1a\u0e40\u0e01\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e2d\u0e25\u0e17\u0e4c \u0e1a\u0e35\u0e1f \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035999 \u0e1a\u0e08.\u0e25\u0e2d\u0e19\u0e14\u0e2d\u0e19\u0e44\u0e1a\u0e40\u0e01\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e2d\u0e25\u0e17\u0e4c \u0e1a\u0e35\u0e1f \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 375\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036014\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f \u0e44\u0e2d \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036014 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f \u0e44\u0e2d \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 268\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036022\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e2d\u0e23\u0e34\u0e0b\u0e2d\u0e19 \u0e44\u0e17\u0e22 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036022 \u0e1a\u0e08.\u0e2e\u0e2d\u0e23\u0e34\u0e0b\u0e2d\u0e19 \u0e44\u0e17\u0e22 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 77\/2   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 201 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0223569000336\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e04 1965\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000336 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e04 1965 2569-07-08 2000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0223569000344\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a. \u0e04\u0e39\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95220\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95220\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000344 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a. \u0e04\u0e39\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-08 2000000 95220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 47\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569001971\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e37\u0e2d\u0e15\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001971 \u0e1a\u0e08.\u0e08\u0e37\u0e2d\u0e15\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u88fd\u9020 666\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0265569000788\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e15\u0e40\u0e01\u0e35\u0e22\u0e27 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000788 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e15\u0e40\u0e01\u0e35\u0e22\u0e27 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 272  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0515569001382\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001382 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e22\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e22\u0e32\u0e15\u0e32\u0e21\u0e43\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e22\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e01\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002093\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002093 \u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 2569-07-08 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 53\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004390\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e25\u0e39\u0e48\u0e08\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004390 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e25\u0e39\u0e48\u0e08\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 91\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0633569000669\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e17\u0e04 \u0e27\u0e34\u0e25\u0e40\u0e25\u0e08\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000669 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e17\u0e04 \u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 2569-07-08 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 98\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0743569000935\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e42\u0e2d\u0e1e\u0e35 \u0e40\u0e2d\u0e40\u0e22\u0e48\u0e19\u0e15\u0e4c \u0e1b\u0e47\u0e2d\u0e1b \u0e04\u0e25\u0e35\u0e19\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000935 \u0e2b\u0e08.\u0e17\u0e35\u0e42\u0e2d\u0e1e\u0e35 \u0e40\u0e2d\u0e40\u0e22\u0e48\u0e19\u0e15\u0e4c \u0e1b\u0e47\u0e2d\u0e1b \u0e04\u0e25\u0e35\u0e19 2569-07-08 2000000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e31\u0e01 \u0e2d\u0e1a \u0e23\u0e35\u0e14 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 10\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007176\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007176 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 83\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0775569002905\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e35\u0e23\u0e35\u0e27\u0e34\u0e27  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002905 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e35\u0e23\u0e35\u0e27\u0e34\u0e27  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23  \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 568  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0775569002913\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e27\u0e42\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002913 \u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e27\u0e42\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 48  \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e25\u0e30\u0e04\u0e32\u0e21 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569012594\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e44\u0e27\u0e15\u0e49\u0e32 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012594 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e44\u0e27\u0e15\u0e49\u0e32 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u533b\u7642\u30fb\u798f\u7949 6\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012608\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e21\u0e32\u0e25\u0e22\u0e32\u0e19 \u0e1a\u0e39\u0e17\u0e35\u0e04 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012608 \u0e1a\u0e08.\u0e01\u0e32\u0e21\u0e32\u0e25\u0e22\u0e32\u0e19 \u0e1a\u0e39\u0e17\u0e35\u0e04 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e32\u0e22\u0e1b\u0e35 \u4e0d\u52d5\u7523 10\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012616\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e21\u0e32 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012616 \u0e1a\u0e08.\u0e19\u0e34\u0e21\u0e32 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e1a\u0e32\u0e23\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012624\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e14\u0e32\u0e23\u0e4c\u0e17\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012624 \u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e14\u0e32\u0e23\u0e4c\u0e17\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47630 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e1b\u0e32\u0e25\u0e39\u0e01\u0e14\u0e2d\u0e01 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012641\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e15\u0e32\u0e01\u0e35\u0e4a \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012641 \u0e1a\u0e08.\u0e40\u0e2d\u0e15\u0e32\u0e01\u0e35\u0e4a \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e04\u0e48\u0e32\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u4e0d\u52d5\u7523 134\/68  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e07 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010141\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010141 \u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 9\/161  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010150\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e22 \u0e2a\u0e1b\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010150 \u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e22 \u0e2a\u0e1b\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 51\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010168\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04 \u0e19\u0e32\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010168 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04 \u0e19\u0e32\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68  \u0e16\u0e19\u0e19\u0e1e\u0e39\u0e25\u0e28\u0e34\u0e23\u0e34 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569127886\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e47\u0e01\u0e40\u0e0b\u0e35\u0e22\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e19\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96109\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96109\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127886 \u0e1a\u0e08.\u0e41\u0e2d\u0e47\u0e01\u0e40\u0e0b\u0e35\u0e22\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e19\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 96109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e23\u0e27\u0e21 ( (holistic wellness & individualized therapy retreat) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21  \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 11\/2  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127932\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e35\u0e22\u0e27\u0e42\u0e01 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127932 \u0e1a\u0e08.\u0e40\u0e04\u0e35\u0e22\u0e27\u0e42\u0e01 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e01\u0e35\u0e49\u0e22\u0e32\u0e01\u0e35\u0e49 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e49\u0e21 \u0e15\u0e38\u0e4b\u0e19 \u0e17\u0e2d\u0e14 \u0e1c\u0e31\u0e14 \u0e1b\u0e34\u0e49\u0e07 \u0e22\u0e48\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e19\u0e17\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21 \u0e0b\u0e2d\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e49\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 7\/5  \u0e16\u0e19\u0e19\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e40\u0e1e\u0e25\u0e0b \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128122\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e04 \u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128122 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e04 \u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 45301 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07-\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32\u0e15\u0e23\u0e32\u0e1420 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128203\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e25\u0e39\u0e42\u0e04 \u0e14\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128203 \u0e1a\u0e08.\u0e2d\u0e25\u0e39\u0e42\u0e04 \u0e14\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 8\/42-1  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b\u0e2d\u0e22 62 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128289\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e1e\u0e25\u0e31\u0e2a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128289 \u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e1e\u0e25\u0e31\u0e2a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e25\u0e44\u0e19\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1788  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e22\u0e39\u0e19\u0e34\u0e15 3002 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128335\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e14\u0e35 \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128335 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e14\u0e35 \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46599 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e25\u0e34\u0e1f\u0e15\u0e4c \u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e19\u0e27\u0e14\u0e34\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38\/346  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 20 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128386\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e48\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128386 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e48\u0e32 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/9   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a3 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e40\u0e27\u0e2c\u0e38\u0e27\u0e19\u0e32\u0e23\u0e32\u0e21 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128416\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e2a\u0e38\u0e02 (\u0e44\u0e21\u0e48) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128416 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e2a\u0e38\u0e02 (\u0e44\u0e21\u0e48) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u533b\u7642\u30fb\u798f\u7949 9\/141  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2e\u0e34\u0e27\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1,2 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 62\/3 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128432\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e39\u0e40\u0e23\u0e35\u0e22\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"53200\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"53200\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128432 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e39\u0e40\u0e23\u0e35\u0e22\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 53200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e38\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 80  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c 3 \u0e41\u0e22\u0e01 5-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128467\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128467 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c usb \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e35\u0e48\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e40\u0e23\u0e47\u0e27 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 594\/5   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 201 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022383\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 88 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e35\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022383 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 88 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e35\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022413\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e2e\u0e23\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022413 \u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e2e\u0e23\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e28\u0e23\u0e35\u0e29\u0e30\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 69\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022448\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e25\u0e14\u0e4c\u0e1e\u0e35\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022448 \u0e1a\u0e08.\u0e44\u0e27\u0e25\u0e14\u0e4c\u0e1e\u0e35\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 498\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022456\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e25\u0e35\u0e17\u0e0b\u0e34\u0e42\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022456 \u0e1a\u0e08.\u0e2d\u0e34\u0e25\u0e35\u0e17\u0e0b\u0e34\u0e42\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 52292 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (freight forwarding) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 333\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025412\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025412 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e41\u0e1f\u0e25\u0e15 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 \u4e0d\u52d5\u7523 27\/110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025501\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e0a\u0e34\u0e23\u0e40\u0e01\u0e37\u0e49\u0e2d\u0e01\u0e32\u0e23\u0e38\u0e13\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025501 \u0e1a\u0e08.\u0e27\u0e0a\u0e34\u0e23\u0e40\u0e01\u0e37\u0e49\u0e2d\u0e01\u0e32\u0e23\u0e38\u0e13\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 87301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e23\u0e30\u0e22\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e41\u0e1a\u0e1a\u0e44\u0e1b-\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e01\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u533b\u7642\u30fb\u798f\u7949 189  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0143569001147\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e08\u0e31\u0e07 \u0e0a\u0e4a\u0e2d\u0e1b\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46434\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46434\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001147 \u0e2b\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e08\u0e31\u0e07 \u0e0a\u0e4a\u0e2d\u0e1b 2569-07-07 2000000 46434 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07  \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e17\u0e33\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e15\u0e32\u0e21\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14   \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14\u0e40\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569035662\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01136\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01136\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035662 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 01136 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e2b\u0e47\u0e14 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 (smart farm) \u0e41\u0e25\u0e30\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e2b\u0e21\u0e48 \u8fb2\u6797\u6c34\u7523 18\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035735\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e0a\u0e35\u0e27\u0e31\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56291\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56291\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035735 \u0e1a\u0e08.\u0e25\u0e32\u0e0a\u0e35\u0e27\u0e31\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 56291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 157\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035743\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2a\u0e15\u0e23\u0e2d\u0e07 \u0e0a\u0e23\u0e34\u0e21\u0e1e\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035743 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2a\u0e15\u0e23\u0e2d\u0e07 \u0e0a\u0e23\u0e34\u0e21\u0e1e\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 195\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035751\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035751 \u0e1a\u0e08.\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 7\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035794\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21\u0e27\u0e35\u0e08\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035794 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21\u0e27\u0e35\u0e08\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data center) \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 \u0e2a\u0e33\u0e23\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 999\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035832\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e2b\u0e22\u0e38\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"26512\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"26512\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035832 \u0e1a\u0e08.\u0e2b\u0e07\u0e2b\u0e22\u0e38\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 26512 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u88fd\u9020 149\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035859\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e01\u0e25\u0e2d\u0e2a\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035859 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e01\u0e25\u0e2d\u0e2a\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 45202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e2a\u0e35\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1b\u0e30\u0e1c\u0e38 \u0e14\u0e32\u0e23\u0e40\u0e04\u0e32\u0e30 \u0e25\u0e2d\u0e01\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035883\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e04\u0e15\u0e49\u0e32 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035883 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e04\u0e15\u0e49\u0e32 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e49\u0e33 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07  \u0e42\u0e14\u0e22\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 212\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035891\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e22\u0e2b\u0e22\u0e27\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035891 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e22\u0e2b\u0e22\u0e27\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b \u0e01\u0e23\u0e23\u0e21 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e16\u0e19\u0e19\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32 \u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u5efa\u8a2d 241\/86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003663\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e1c\u0e49\u0e32 365 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003663 \u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e1c\u0e49\u0e32 365 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569007021\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e22 \u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007021 \u0e1a\u0e08.\u0e2a\u0e27\u0e22 \u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22\u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 457  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007030\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e17\u0e21\u0e32\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007030 \u0e1a\u0e08.\u0e1b\u0e31\u0e17\u0e21\u0e32\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e14\u0e22\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e42\u0e14\u0e22\u0e1b\u0e01\u0e15\u0e34 \u0e08\u0e30\u0e1c\u0e48\u0e32\u0e19 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007064\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007064 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 211\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0345569003051\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e19\u0e08\u0e34\u0e23\u0e32 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003051 \u0e1a\u0e08.\u0e40\u0e08\u0e19\u0e08\u0e34\u0e23\u0e32 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003505\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e23\u0e35 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003505 \u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e23\u0e35 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c (guesthouse) \u5bbf\u6cca\u30fb\u98f2\u98df 19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0475569001430\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e19 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001430 \u0e1a\u0e08.\u0e41\u0e1e\u0e19 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015260\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e23\u0e20\u0e35 \u0e41\u0e2d\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015260 \u0e1a\u0e08.\u0e2a\u0e32\u0e23\u0e20\u0e35 \u0e41\u0e2d\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015316\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e04\u0e23\u0e39\u0e17\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015316 \u0e1a\u0e08.\u0e2a\u0e04\u0e23\u0e39\u0e17\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e23\u0e30\u0e1a\u0e1a \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e08\u0e32\u0e30\u0e23\u0e30\u0e1a\u0e1a (penetration testing)  \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 89  \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004349\",\"name_th\":\"\u0e1a\u0e08.299 \u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004349 \u0e1a\u0e08.299 \u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 45201 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e33\u0e2a\u0e35 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2a\u0e35 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e16 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004357\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e0a\u0e0a\u0e32\u0e20\u0e32 \u0e2d\u0e34\u0e21\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004357 \u0e1a\u0e08.\u0e1e\u0e34\u0e0a\u0e0a\u0e32\u0e20\u0e32 \u0e2d\u0e34\u0e21\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e16\u0e48\u0e32\u0e19 \u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e41\u0e2d\u0e04\u0e15\u0e34\u0e40\u0e27\u0e17\u0e40\u0e15\u0e47\u0e04\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e16\u0e48\u0e32\u0e19\u0e01\u0e31\u0e21\u0e21\u0e31\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569001942\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (2529) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001942 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (2529) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e42\u0e21\u0e08\u0e34 \u0e0a\u0e47\u0e2d\u0e01\u0e42\u0e01\u0e41\u0e25\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca \u0e0849\/63,\u0e0855\/120  \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0735569006897\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35 365 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006897 \u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35 365 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47524 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 116\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006901\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35 369 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006901 \u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35 369 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47524 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 116\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006919\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35 789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006919 \u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35 789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 47524 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 116\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007133\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e40\u0e0b\u0e35\u0e22\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10133\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10133\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007133 \u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e40\u0e0b\u0e35\u0e22\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 10133 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 32\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0805569002602\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e082 \u0e40\u0e04 \u0e44\u0e1a\u0e42\u0e2d (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002602 \u0e1a\u0e08.\u0e40\u0e082 \u0e40\u0e04 \u0e44\u0e1a\u0e42\u0e2d (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 392\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569012551\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e40\u0e1a\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012551 \u0e1a\u0e08.\u0e2d\u0e23\u0e40\u0e1a\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e42\u0e14\u0e22\u0e17\u0e33\u0e41\u0e17\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e41\u0e17\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2a\u0e34\u0e19 \u4e0d\u52d5\u7523 19\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010095\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e22 \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1a\u0e35\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010095 \u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e22 \u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1a\u0e35\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 124\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0915569000331\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e1f\u0e23\u0e4c\u0e41\u0e04\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0915569000331 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e1f\u0e23\u0e4c\u0e41\u0e04\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 1432\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0955569000536\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000536 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 2000000 46313 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49  \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e07\u0e32\u0e30 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e25\u0e33\u0e44\u0e22 \u0e2b\u0e23\u0e37\u0e2d \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569126987\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e42\u0e19\u0e27\u0e32 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126987 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e42\u0e19\u0e27\u0e32 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e41\u0e01\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e31\u0e19\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 28\/50  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e25\u0e34\u0e19\u0e2d\u0e40\u0e27\u0e19\u0e34\u0e27 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127096\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127096 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1000\/9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e27\u0e34\u0e0a\u0e31\u0e19\u0e19\u0e32\u0e23\u0e35\u0e1b\u0e32\u0e23\u0e4c\u0e04-\u0e40\u0e0b\u0e32\u0e18\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1210a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127100\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e08\u0e35\u0e41\u0e2d\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127100 \u0e1a\u0e08.\u0e40\u0e2d\u0e08\u0e35\u0e41\u0e2d\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 514  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127177\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e0b\u0e35\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127177 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e0b\u0e35\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e32\u0e23\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 736 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127444\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49\u0e1a\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127444 \u0e1a\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49\u0e1a\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (electronic commerce) \u0e2b\u0e23\u0e37\u0e2d \u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b (e-commerce) \u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30 (social media) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-marketplace) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e43\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 (\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1788  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e22\u0e39\u0e19\u0e34\u0e15 3001 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127592\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e15\u0e17\u0e2d\u0e22 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127592 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e15\u0e17\u0e2d\u0e22 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46109 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 904\/111  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e04\u0e25\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e41\u0e01\u0e49\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022251\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e25\u0e34\u0e15\u0e32  \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022251 \u0e1a\u0e08.\u0e0a\u0e25\u0e34\u0e15\u0e32  \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e32\u0e22\u0e0a\u0e32\u0e23\u0e4c\u0e08  \u0e2b\u0e39\u0e1f\u0e31\u0e07  \u0e40\u0e04\u0e2a  \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/391  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022308\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e44\u0e09 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022308 \u0e1a\u0e08.\u0e42\u0e1b\u0e44\u0e09 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e40\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e40\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 501\/146  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025021\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32\u0e25\u0e4c\u0e27\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025021 \u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32\u0e25\u0e4c\u0e27\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46105 \u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a \u0e19\u0e49\u0e33 \u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e41\u0e2d\u0e23\u0e4c \u0e19\u0e49\u0e33\u0e40\u0e22\u0e47\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/436  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e2d\u0e19\u0e40\u0e08\u0e14\u0e35\u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 535 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 6 \u0e41\u0e22\u0e01 3\/1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025200\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01629\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01629\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025200 \u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 01629 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u8fb2\u6797\u6c34\u7523 13\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025218\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e40\u0e1b\u0e0b\u0e42\u0e2e\u0e21 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025218 \u0e1a\u0e08.\u0e2a\u0e40\u0e1b\u0e0b\u0e42\u0e2e\u0e21 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 100\/211  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035441\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1a \u0e22\u0e27\u0e19 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035441 \u0e1a\u0e08.\u0e42\u0e1a \u0e22\u0e27\u0e19 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a ( \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 ) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 99\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035506\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e21\u0e34\u0e19\u0e35 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035506 \u0e1a\u0e08.\u0e40\u0e08\u0e21\u0e34\u0e19\u0e35 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 479\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035522\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2d\u0e40\u0e25\u0e41\u0e1f\u0e19\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035522 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2d\u0e40\u0e25\u0e41\u0e1f\u0e19\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e22\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e42\u0e14\u0e23\u0e25\u0e34\u0e04 \u88fd\u9020 188\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035531\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e07\u0e1b\u0e31\u0e07 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035531 \u0e1a\u0e08.\u0e1b\u0e31\u0e07\u0e1b\u0e31\u0e07 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 585\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035638\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0a\u0e19\u0e48\u0e32 \u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e01\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035638 \u0e1a\u0e08.\u0e44\u0e0a\u0e19\u0e48\u0e32 \u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e01\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 55\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0223569000328\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23 88\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000328 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23 88 2569-07-06 2000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007013\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e35\u0e48\u0e40\u0e0b\u0e0a\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0305569007013 \u0e1a\u0e08.\u0e22\u0e35\u0e48\u0e40\u0e0b\u0e0a\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 444\/40  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e40\u0e1b\u0e0b  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 vo-015 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006458\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e25\u0e31\u0e19\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46415\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46415\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006458 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e25\u0e31\u0e19\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46415 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001543\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e1e\u0e17\u0e19\u0e32\u0e23\u0e16\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001543 \u0e2b\u0e08.\u0e44\u0e1e\u0e17\u0e19\u0e32\u0e23\u0e16\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 2569-07-06 2000000 86909 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16 \u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e1a\u0e32\u0e14\u0e40\u0e08\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e39\u0e49\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e07\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u533b\u7642\u30fb\u798f\u7949 141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0475569001413\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e07\u0e1b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0475569001413 \u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e07\u0e1b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 444\/39  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e40\u0e1b\u0e0b  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 vo-010 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015197\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015197 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a\u0e21\u0e37\u0e2d \u0e40\u0e25\u0e47\u0e1a\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e2a\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 30\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0615569000474\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000474 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0615569000482\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e19\u0e32\u0e23\u0e32 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000482 \u0e1a\u0e08.\u0e42\u0e21\u0e19\u0e32\u0e23\u0e32 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 204  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e17\u0e38\u0e48\u0e07 \u0e40\u0e0a\u0e37\u0e2d\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0615569000491\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e0b\u0e35 \u0e40\u0e17\u0e23\u0e14 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000491 \u0e1a\u0e08.\u0e14\u0e35\u0e0b\u0e35 \u0e40\u0e17\u0e23\u0e14 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0615569000504\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e19\u0e31\u0e17 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000504 \u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e19\u0e31\u0e17 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0655569002141\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e48\u0e32 \u0e23\u0e39\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002141 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e48\u0e32 \u0e23\u0e39\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 605\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0675569001420\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32 \u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001420 \u0e1a\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32 \u0e18\u0e07\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0735569006820\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006820 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (procurement \/ sourcing) \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007044\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c 9656  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007044 \u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c 9656  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 33200 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 32\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007052\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e40\u0e0b\u0e19 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46492\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46492\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007052 \u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e40\u0e0b\u0e19 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e40\u0e1b\u0e49 \u0e17\u0e38\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 84   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 d7 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007061\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e01\u0e42\u0e19\u0e40\u0e25\u0e35\u0e22 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20292\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20292\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007061 \u0e1a\u0e08.\u0e41\u0e21\u0e01\u0e42\u0e19\u0e40\u0e25\u0e35\u0e22 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 20292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e01\u0e32\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e01\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e1a\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e09\u0e32\u0e01\u0e40\u0e02\u0e49\u0e32\u0e21\u0e38\u0e21 \u0e41\u0e01\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e16\u0e19\u0e2d\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e41\u0e01\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 48\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569005368\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005368 \u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46109 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005376\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e17\u0e22\u0e31\u0e07 \u0e15\u0e25\u0e32\u0e14\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005376 \u0e1a\u0e08.\u0e41\u0e17\u0e22\u0e31\u0e07 \u0e15\u0e25\u0e32\u0e14\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 2000000 46109 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569126774\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126774 \u0e1a\u0e08.\u0e1e\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 2000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 48 \u0e41\u0e22\u0e01 17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569020666\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e19\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020666 \u0e1a\u0e08.\u0e42\u0e0b\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e19\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e27\u0e07 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0515569001358\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e0a \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001358 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e0a \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 2000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569126561\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2d\u0e2a\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126561 \u0e1a\u0e08.\u0e21\u0e2d\u0e2a\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e44\u0e25\u0e48\u0e41\u0e21\u0e25\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 v06 \u0e0b\u0e2d\u0e22 \u0e2a\u0e35\u0e25\u0e219 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569035352\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e0b\u0e35 \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035352 \u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e0b\u0e35 \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 59\/245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035379\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e1f\u0e39\u0e48 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035379 \u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e1f\u0e39\u0e48 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 2000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118\/90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001171\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e19\u0e25 \u0e1a\u0e32\u0e22 \u0e40\u0e21\u0e08\u0e34\u0e01\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001171 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e19\u0e25 \u0e1a\u0e32\u0e22 \u0e40\u0e21\u0e08\u0e34\u0e01 2569-07-04 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 559\/182  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015138\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e17\u0e35 \u0e0b\u0e35 \u0e17\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015138 \u0e1a\u0e08.\u0e40\u0e2d \u0e17\u0e35 \u0e0b\u0e35 \u0e17\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e40\u0e0a\u0e48\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e1f\u0e23\u0e15 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e42\u0e14\u0e22\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e49\u0e27\u0e41\u0e1a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e48\u0e2d\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e0d\u52d5\u7523 39\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0735569006757\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e42\u0e1f\u0e23 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006757 \u0e1a\u0e08.\u0e40\u0e19\u0e42\u0e1f\u0e23 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 2000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e44\u0e15\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1f\u0e2d\u0e01\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e15\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e44\u0e15 \u533b\u7642\u30fb\u798f\u7949 135\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0863569000403\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e28\u0e34\u0e21\u0e32 \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0863569000403 \u0e2b\u0e08.\u0e28\u0e28\u0e34\u0e21\u0e32 \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 2569-07-04 2000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569125697\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125697 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 678\/7  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125727\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e1e\u0e35 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e32 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125727 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e1e\u0e35 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e32 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 (business transformation) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 (digital transformation \/ it consulting) \u0e43\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 153\/303  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 89\/1 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125905\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125905 \u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e01\u0e2a\u0e20\u0e32\u0e1e \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 305\/113  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19 12 \u0e41\u0e22\u0e01 1-2-3-5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125930\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e31\u0e27 \u0e0b\u0e35 \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125930 \u0e1a\u0e08.\u0e2b\u0e31\u0e27 \u0e0b\u0e35 \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e35 23 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125948\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e40\u0e2d\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62021\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62021\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125948 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e40\u0e2d\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 62021 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a (system integration services) \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a (operation & maintenance services) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e35 23 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126022\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e4c\u0e1b\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126022 \u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e4c\u0e1b\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e23\u0e16\u0e1a\u0e31\u0e2a\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e16\u0e44\u0e1f \u0e40\u0e23\u0e37\u0e2d \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 89\/12  \u0e16\u0e19\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126057\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e34\u0e21\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126057 \u0e1a\u0e08.\u0e22\u0e34\u0e21\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 388 \u0e0a\u0e31\u0e49\u0e19 8  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126073\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e39\u0e21\u0e0b\u0e2d\u0e1f\u0e17\u0e4c \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126073 \u0e1a\u0e08.\u0e1e\u0e39\u0e21\u0e0b\u0e2d\u0e1f\u0e17\u0e4c \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 47723 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/23  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04.\u0e0b\u0e35.\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e42\u0e2e\u0e21 \u0e0b\u0e2d\u0e22 \u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126090\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e0b\u0e35 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126090 \u0e1a\u0e08.\u0e42\u0e19\u0e0b\u0e35 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 73102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c111 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126201\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e21\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126201 \u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e21\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e38\u0e04\u0e25\u0e34\u0e01\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 2089\/15  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126227\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e49\u0e40\u0e08\u0e4b\u0e2d \u0e2d\u0e30\u0e1a\u0e31\u0e19\u0e41\u0e14\u0e19\u0e17\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126227 \u0e1a\u0e08.\u0e2d\u0e35\u0e49\u0e40\u0e08\u0e4b\u0e2d \u0e2d\u0e30\u0e1a\u0e31\u0e19\u0e41\u0e14\u0e19\u0e17\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u904b\u8f38\u30fb\u7269\u6d41 426\/2-3   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 203 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e48\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126294\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e14\u0e14\u0e35\u0e49\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126294 \u0e1a\u0e08.\u0e40\u0e23\u0e14\u0e14\u0e35\u0e49\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 15  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e23.\u0e59 \u0e0b.26 \u0e41\u0e22\u0e012 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126405\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e2d\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126405 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e2d\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e22\u0e39\u0e19\u0e34\u0e15 4 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126421\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e4c\u0e27\u0e32\u0e19\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126421 \u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e4c\u0e27\u0e32\u0e19\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 (\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u533b\u7642\u30fb\u798f\u7949 45\/5-6  \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e44\u0e0a\u0e22\u0e28\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021948\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e18\u0e2d\u0e2a \u0e2e\u0e2d\u0e25\u0e1b\u0e34\u0e17\u0e31\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021948 \u0e1a\u0e08.\u0e41\u0e2d\u0e18\u0e2d\u0e2a \u0e2e\u0e2d\u0e25\u0e1b\u0e34\u0e17\u0e31\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/350  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024831\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e17 \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e17\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18122\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18122\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024831 \u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e17 \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e17\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 18122 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e1c\u0e48\u0e19\u0e44\u0e27\u0e19\u0e34\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e4a\u0e19\u0e17\u0e4c\u0e44\u0e27\u0e19\u0e34\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e4a\u0e19\u0e17\u0e4c\u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e37\u0e48\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e44\u0e27\u0e19\u0e34\u0e25 \u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1c\u0e25\u0e34\u0e15\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e25\u0e07\u0e1a\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u88fd\u9020 69\/899  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024947\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024947 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 23\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0145569004385\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e44\u0e17\u0e48 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004385 \u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e44\u0e17\u0e48 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 168-176  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0203569002797\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e19\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e32\u0e08\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002797 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e19\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e32\u0e08 2569-07-03 2000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e17\u0e33\u0e2a\u0e35 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035174\",\"name_th\":\"\u0e1a\u0e08.\u0e2a.\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 88 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"53200\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"53200\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035174 \u0e1a\u0e08.\u0e2a.\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 88 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 53200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e19\u0e33\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u904b\u8f38\u30fb\u7269\u6d41 111\/3,111\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035247\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e2d\u0e35\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035247 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e2d\u0e35\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 105\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003604\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0b\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003604 \u0e1a\u0e08.\u0e44\u0e0b\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0403569002906\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002906 \u0e2b\u0e08.\u0e1a\u0e35\u0e27\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-03 2000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 (hvac) \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (cctv) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e20\u0e32\u0e1e \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32-\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 231  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006393\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006393 \u0e1a\u0e08.\u0e40\u0e2d\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 433   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006407\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e25\u0e42\u0e27\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006407 \u0e1a\u0e08.\u0e40\u0e1a\u0e25\u0e42\u0e27\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006415\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e25\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006415 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e25\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001391\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e23\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001391 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e23\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 263  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015049\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e1e\u0e35 \u0e14\u0e35 \u0e0b\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015049 \u0e1a\u0e08.\u0e23\u0e1e\u0e35 \u0e14\u0e35 \u0e0b\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 101\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48-\u0e1d\u0e32\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0655569002094\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e08\u0e42\u0e2d\u0e2c\u0e32\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002094 \u0e1a\u0e08.\u0e01\u0e34\u0e08\u0e42\u0e2d\u0e2c\u0e32\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e32\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 69\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0775569002867\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002867 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 10\/136  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569012446\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e40\u0e27\u0e25\u0e1f\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012446 \u0e1a\u0e08.\u0e17\u0e40\u0e27\u0e25\u0e1f\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e01\u0e2a\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 99\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0905569005287\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e20\u0e31\u0e17\u0e23 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1a\u0e34\u0e49\u0e27\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005287 \u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e20\u0e31\u0e17\u0e23 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1a\u0e34\u0e49\u0e27\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005295\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e2a\u0e21\u0e32\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005295 \u0e1a\u0e08.\u0e2d\u0e38\u0e2a\u0e21\u0e32\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005309\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e31\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005309 \u0e1a\u0e08.\u0e1b\u0e32\u0e19\u0e0a\u0e35\u0e27\u0e31\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005317\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e32\u0e14\u0e4a\u0e30 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005317 \u0e1a\u0e08.\u0e09\u0e32\u0e14\u0e4a\u0e30 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 2000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569124763\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e17\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e35\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124763 \u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e17\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e35\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 777\/4  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1a\u0e33\u0e40\u0e1e\u0e47\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124895\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124895 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 69200 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 28 \u0e41\u0e22\u0e01 34 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124933\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124933 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u533b\u7642\u30fb\u798f\u7949 827\/4   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 d6-d7 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 85-85\/1 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124941\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e2d\u0e42\u0e28\u0e01) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124941 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e2d\u0e42\u0e28\u0e01) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u533b\u7642\u30fb\u798f\u7949 246  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e44\u0e17\u0e21\u0e2a\u0e4c \u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 416-417 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124950\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124950 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u533b\u7642\u30fb\u798f\u7949 1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e25\u0e2a44  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 m1 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e325 \u0e41\u0e22\u0e0124 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124992\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124992 \u0e1a\u0e08.\u0e18\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 43210 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u5efa\u8a2d 44  \u0e0b\u0e2d\u0e22 \/\u0e15\u0e23\u0e2d\u0e01\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e1e\u0e34\u0e21\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125077\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1f\u0e23\u0e35 \u0e44\u0e25\u0e1a\u0e23\u0e32\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125077 \u0e1a\u0e08.\u0e41\u0e04\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1f\u0e23\u0e35 \u0e44\u0e25\u0e1a\u0e23\u0e32\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 (specialty coffee cafe) \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 10\/15  \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125158\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125158 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79  \u0e0b\u0e2d\u0e22 \u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02 26 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125221\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125221 \u0e1a\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e42\u0e1b\u0e23\u0e42\u0e21\u0e17\u0e04\u0e25\u0e34\u0e1b\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01 \u0e22\u0e39\u0e17\u0e39\u0e1a \u0e15\u0e34\u0e4a\u0e01\u0e15\u0e4a\u0e2d\u0e01 \u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e32\u0e41\u0e01\u0e23\u0e21  \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2d\u0e44\u0e2d \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1468\/5  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125239\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125239 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 989  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e22\u0e32\u0e21\u0e1e\u0e34\u0e27\u0e23\u0e23\u0e18\u0e19\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e17\u0e35\u0e17\u0e3522 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e40\u0e2d \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125298\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e15\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125298 \u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e15\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 73200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (influencer) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e2a\u0e23\u0e23\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 influencer \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 51\/40  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125361\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e27\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125361 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e27\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 725  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e42\u0e17\u0e23  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 166 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125379\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e39\u0e14\u0e32\u0e22\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125379 \u0e1a\u0e08.\u0e2d\u0e39\u0e14\u0e32\u0e22\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 10  \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125468\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e14\u0e39 \u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125468 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e2d\u0e14\u0e39 \u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e39\u0e14 \u0e01\u0e32\u0e23\u0e2d\u0e48\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u6559\u80b2 80  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c 3 \u0e41\u0e22\u0e01 5-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125484\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e04\u0e34\u0e27-\u0e40\u0e21\u0e17 \u0e17\u0e39\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125484 \u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e04\u0e34\u0e27-\u0e40\u0e21\u0e17 \u0e17\u0e39\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e40\u0e2d4 \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e21\u0e19\u0e18\u0e32\u0e15\u0e38\u0e2f \u0e41\u0e22\u0e01 35-9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125603\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e19\u0e14\u0e23\u0e49\u0e32 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58192\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58192\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125603 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e19\u0e14\u0e23\u0e49\u0e32 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 58192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 1599\/270  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125620\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c11 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125620 \u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c11 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 21\/17  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 60 \u0e41\u0e22\u0e01 1 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021832\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2a\u0e40\u0e1b\u0e0b\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021832 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2a\u0e40\u0e1b\u0e0b\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0b\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e43\u0e14\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e15\u0e36\u0e01\u0e41\u0e16\u0e27 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 335\/331  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 38\/1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569020534\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 159 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46415\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46415\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020534 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 159 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 46415 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0245569003574\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e04\u0e27\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0245569003574 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e04\u0e27\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07 \u0e17\u0e31\u0e48\u0e07\u0e21\u0e34\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0245569003582\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003582 \u0e1a\u0e08.\u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0405569006288\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006288 \u0e1a\u0e08.\u0e40\u0e2d \u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 456\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0473569000865\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e40\u0e2e\u0e07\u0e40\u0e2e\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000865 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e40\u0e2e\u0e07\u0e40\u0e2e\u0e07 2569-07-02 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 67  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001383\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e27\u0e35\u0e48\u0e40\u0e27\u0e48\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001383 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e27\u0e35\u0e48\u0e40\u0e27\u0e48\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569014930\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85601\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85601\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014930 \u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 85601 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e48\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e35\u0e01\u0e29\u0e32(\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u6559\u80b2 99\/133  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014981\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014981 \u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e20\u0e32\u0e1e\u0e07\u0e32\u0e19 \u0e20\u0e32\u0e1e\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 101\/21  \u0e16\u0e19\u0e19\u0e40\u0e27\u0e35\u0e22\u0e07\u0e1e\u0e34\u0e07\u0e04\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0585569000254\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e41\u0e1f\u0e25\u0e0a \u0e08\u0e35\u0e40\u0e2d\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\",\"province_ja\":\"\u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\",\"search_text\":\"0585569000254 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e41\u0e1f\u0e25\u0e0a \u0e08\u0e35\u0e40\u0e2d\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0635569001373\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001373 \u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e14\u0e33\u0e2b\u0e23\u0e34 1 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0815569002017\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e15\u0e34\u0e19\u0e48\u0e32 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002017 \u0e1a\u0e08.\u0e42\u0e21\u0e15\u0e34\u0e19\u0e48\u0e32 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 257  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0825569001070\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001070 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 55102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e48\u0e07\u0e2b\u0e49\u0e2d\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 43\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569012365\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e14\u0e34\u0e2a\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012365 \u0e1a\u0e08.\u0e42\u0e01\u0e14\u0e34\u0e2a\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 62022 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e44\u0e2d\u0e17\u0e35 \u60c5\u5831\u901a\u4fe1\u30fbit 30\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012373\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e21 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49209\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49209\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012373 \u0e1a\u0e08.\u0e42\u0e2d\u0e21 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 49209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e1a\u0e31\u0e2a \u0e23\u0e16\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u904b\u8f38\u30fb\u7269\u6d41 51\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012381\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e1f\u0e42\u0e1f\u0e23 \u0e23\u0e39\u0e21 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012381 \u0e1a\u0e08.\u0e41\u0e2d\u0e1f\u0e42\u0e1f\u0e23 \u0e23\u0e39\u0e21 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 64\/5  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e25\u0e32 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012411\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012411 \u0e1a\u0e08.\u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07  \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 69\/469  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010028\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e04\u0e32\u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010028 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e04\u0e32\u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 22220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e35\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u88fd\u9020 88\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010036\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010036 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 28\/259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010044\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010044 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14          \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005228\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005228 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 2000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e0b\u0e2d\u0e22 6\/1 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e04\u0e23\u0e21\u0e07\u0e04\u0e25 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569006491\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e27\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006491 \u0e2b\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e27\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c 2569-07-01 2000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 75\/5  \u0e0b\u0e2d\u0e22 \u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 4 \u0e0b\u0e2d\u0e2254 \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123911\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e44\u0e2d\u0e1e\u0e35 \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62021\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62021\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123911 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e44\u0e2d\u0e1e\u0e35 \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 62021 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 357\/10  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 54\/4 \u0e41\u0e22\u0e01 1-4 (\u0e01\u0e39\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e342) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124011\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e21\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124011 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e21\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u5efa\u8a2d 89\/86  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124101\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e2d  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124101 \u0e1a\u0e08.\u0e22\u0e39\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e2d  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 72102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e17\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e14\u0e39\u0e41\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e42\u0e14\u0e22\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e02\u0e49\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 102\/42  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e31\u0e14\u0e14\u0e32\u0e23\u0e21\u0e22\u0e4c \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 118 \u0e41\u0e22\u0e01 44-4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124208\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e1d\u0e39 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124208 \u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e1d\u0e39 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 952  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e32\u0e21\u0e32\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 13 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124283\",\"name_th\":\"\u0e1a\u0e08.17 \u0e04\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124283 \u0e1a\u0e08.17 \u0e04\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 77101 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 890\/1  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124305\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e17\u0e23\u0e19\u0e0b\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124305 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e17\u0e23\u0e19\u0e0b\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 72101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 287  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e25\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124313\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e40\u0e01\u0e25 \u0e44\u0e27\u0e2a\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124313 \u0e1a\u0e08.\u0e2a\u0e40\u0e01\u0e25 \u0e44\u0e27\u0e2a\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19  \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 19\/37  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e40\u0e1e\u0e25\u0e2a \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124348\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e22 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124348 \u0e1a\u0e08.\u0e2d\u0e31\u0e22 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 52 \u0e41\u0e22\u0e01 10 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124615\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e19\u0e42\u0e15\u0e30 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124615 \u0e1a\u0e08.\u0e23\u0e31\u0e19\u0e42\u0e15\u0e30 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1840  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e2e\u0e34\u0e25\u0e25\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 826 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124658\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e19\u0e32\u0e19\u0e32\u0e1f\u0e23\u0e38\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0105569124658 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e19\u0e32\u0e19\u0e32\u0e1f\u0e23\u0e38\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0113569002186\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e23\u0e32 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002186 \u0e2b\u0e08.\u0e19\u0e32\u0e23\u0e32 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 2569-07-01 2000000 68103 \u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 1224\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021581\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e17 \u0e41\u0e21\u0e17\u0e0a\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021581 \u0e1a\u0e08.\u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e17 \u0e41\u0e21\u0e17\u0e0a\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e41\u0e21\u0e17\u0e0a\u0e34\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 270\/227  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e43\u0e2b\u0e0d\u0e4b \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021620\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e17\u0e4c\u0e44\u0e27\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021620 \u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e17\u0e4c\u0e44\u0e27\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e34\u0e14\u0e04\u0e49\u0e19 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence: ai) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data analytics) \u60c5\u5831\u901a\u4fe1\u30fbit 88\/205  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021719\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e42\u0e2e\u0e21 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46412\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46412\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021719 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e42\u0e2e\u0e21 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46412 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024491\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e2d\u0e15\u0e25\u0e32\u0e2a \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024491 \u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e2d\u0e15\u0e25\u0e32\u0e2a \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 49334 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1b\u0e25\u0e2d\u0e14\u0e2d\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e42\u0e14\u0e22 \u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e02\u0e15\u0e1b\u0e25\u0e2d\u0e14\u0e2d\u0e32\u0e01\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47 \u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e49\u0e27) \u904b\u8f38\u30fb\u7269\u6d41 89\/54  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e18\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024661\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024661 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020194\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e25\u0e34\u0e14\u0e14\u0e35\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020194 \u0e1a\u0e08.\u0e2a\u0e25\u0e34\u0e14\u0e14\u0e35\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 5\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020208\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e23\u0e4c\u0e22\u0e48\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020208 \u0e1a\u0e08.\u0e0b\u0e2d\u0e23\u0e4c\u0e22\u0e48\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 84  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020267\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25-\u0e2d\u0e32\u0e21\u0e35\u0e19 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020267 \u0e1a\u0e08.\u0e2d\u0e31\u0e25-\u0e2d\u0e32\u0e21\u0e35\u0e19 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e2e\u0e31\u0e08\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2e\u0e31\u0e08\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e21\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 59\/26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020283\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e49\u0e32 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020283 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e49\u0e32 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 969\/373  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e31\u0e2a\u0e2a\u0e23 4 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020372\",\"name_th\":\"\u0e1a\u0e08. \u0e2b\u0e21\u0e34\u0e07\u0e2e\u0e31\u0e48\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020372 \u0e1a\u0e08. \u0e2b\u0e21\u0e34\u0e07\u0e2e\u0e31\u0e48\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 10309 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e16\u0e31\u0e48\u0e27\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e43\u0e19\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1b\u0e34\u0e14\u0e1c\u0e19\u0e36\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e2a\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u88fd\u9020 25\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020437\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e38\u0e48\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020437 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e38\u0e48\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020445\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e44\u0e27\u0e19\u0e34\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020445 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e44\u0e27\u0e19\u0e34\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004351\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004351 \u0e1a\u0e08.\u0e44\u0e1e\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0195569002382\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e42\u0e15\u0e30 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002382 \u0e1a\u0e08.\u0e25\u0e34\u0e42\u0e15\u0e30 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 179\/5  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e1b\u0e32\u0e23\u0e4c\u0e04  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 pz12-005\/a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 0 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e14\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034640\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 414 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034640 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 414 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 453\/277  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034666\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e2d\u0e2a \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034666 \u0e1a\u0e08.\u0e04\u0e23\u0e2d\u0e2a \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 10751 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07 \u0e14\u0e49\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e32\u0e29\u0e35 \u88fd\u9020 88\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034712\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e41\u0e2d\u0e25 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034712 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e41\u0e2d\u0e25 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 303\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034739\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e35\u0e44\u0e09 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034739 \u0e1a\u0e08.\u0e0a\u0e35\u0e44\u0e09 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e08\u0e2d\u0e07\u0e1a\u0e31\u0e15\u0e23\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e08\u0e2d\u0e07\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 188\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034771\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e32\u0e15\u0e49\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034771 \u0e1a\u0e08.\u0e15\u0e32\u0e15\u0e49\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a business center \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e1e\u0e22\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 238\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034861\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e40\u0e15\u0e22\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e17\u0e39\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034861 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e40\u0e15\u0e22\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e17\u0e39\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 246\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034887\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e19\u0e42\u0e14\u0e49 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034887 \u0e1a\u0e08.\u0e40\u0e04\u0e19\u0e42\u0e14\u0e49 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e21\u0e25\u0e49\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e01\u0e39\u0e4a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48  \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008746\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008746 \u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\\\"\\\" \u904b\u8f38\u30fb\u7269\u6d41 88\/142  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e1a\u0e25\u0e34\u0e0b \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e193574 \u0e1b\u0e25\u0e27\u0e01\u0e41\u0e14\u0e07 - \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003558\",\"name_th\":\"\u0e1a\u0e08.59 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35302\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35302\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003558 \u0e1a\u0e08.59 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 35302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32, \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0a\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 89\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0403569002884\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002884 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 2569-07-01 2000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003394\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e2d\u0e38\u0e14\u0e21 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003394 \u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e2d\u0e38\u0e14\u0e21 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 188  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569014808\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e42\u0e1f\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014808 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e42\u0e1f\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/2  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e27\u0e07\u0e04\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0625569000741\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e32\u0e2a\u0e22\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000741 \u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e32\u0e2a\u0e22\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e2a\u0e14 \u0e1b\u0e25\u0e32\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e1b\u0e25\u0e32\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 144\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0655569002051\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e38\u0e17\u0e18\u0e19\u0e0a\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002051 \u0e1a\u0e08.\u0e28\u0e38\u0e17\u0e18\u0e19\u0e0a\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 999\/220  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0745569006960\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e07\u0e2b\u0e22\u0e39\u0e48 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569006960 \u0e1a\u0e08.\u0e08\u0e07\u0e2b\u0e22\u0e39\u0e48 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0845569009976\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e0b\u0e35\u0e48 \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569009976 \u0e1a\u0e08.\u0e25\u0e39\u0e0b\u0e35\u0e48 \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 99\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005147\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e41\u0e2d\u0e25 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005147 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e41\u0e2d\u0e25 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e02\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 89  \u0e0b\u0e2d\u0e22 3 \u0e08\u0e38\u0e11\u0e32\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005180\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005180 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 117\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005210\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1c\u0e34\u0e27\u0e2a\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":2000000,\"capital_display\":\"2,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005210 \u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1c\u0e34\u0e27\u0e2a\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 2000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e2a\u0e1b\u0e32\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e27 \u0e1d\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e14\u0e48\u0e32\u0e07\u0e14\u0e33\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 19\/5  \u0e0b\u0e2d\u0e22 27(\u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e1a\u0e38\u0e23\u0e35) \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0835569013868\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e0b\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1900000,\"capital_display\":\"1,900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013868 \u0e1a\u0e08.\u0e17\u0e35\u0e0b\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1900000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0483569000482\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e0b\u0e1f\u0e42\u0e0b\u0e19\u0e01\u0e32\u0e23\u0e32\u0e08\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1820000,\"capital_display\":\"1,820,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000482 \u0e2b\u0e08.\u0e40\u0e0b\u0e1f\u0e42\u0e0b\u0e19\u0e01\u0e32\u0e23\u0e32\u0e08 2569-07-01 1820000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0193569000833\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e35.\u0e40\u0e2d\u0e2a. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1800000,\"capital_display\":\"1,800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000833 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e35.\u0e40\u0e2d\u0e2a. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-24 1800000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 404\/160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569129625\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1800000,\"capital_display\":\"1,800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129625 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1800000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\/\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 117  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c28 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022031\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e19\u0e17\u0e4c \u0e1a\u0e39\u0e17\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1800000,\"capital_display\":\"1,800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022031 \u0e1a\u0e08.\u0e21\u0e34\u0e19\u0e17\u0e4c \u0e1a\u0e39\u0e17\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1800000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 400  \u0e16\u0e19\u0e19\u0e28\u0e34\u0e23\u0e34\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569008044\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e34\u0e19\u0e40\u0e17\u0e08\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1700000,\"capital_display\":\"1,700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008044 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e34\u0e19\u0e40\u0e17\u0e08 2569-07-24 1700000 14112 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u88fd\u9020 10\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136800\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e21\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1700000,\"capital_display\":\"1,700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136800 \u0e1a\u0e08.\u0e21\u0e34\u0e21\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1700000 46443 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e2d\u0e32\u0e22\u0e38 3 \u0e1b\u0e35 \u0e08\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/42  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e21\u0e40\u0e21\u0e19\u0e40\u0e18\u0e35\u0e22 \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01008 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026117\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e17\u0e35\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1700000,\"capital_display\":\"1,700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026117 \u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e17\u0e35\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1700000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 89\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0353569000505\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e32\u0e0a\u0e32\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e22\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1600000,\"capital_display\":\"1,600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000505 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e32\u0e0a\u0e32\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e22 2569-07-27 1600000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c  \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 66  \u0e16\u0e19\u0e19\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0303569003016\",\"name_th\":\"\u0e2b\u0e08.36 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569003016 \u0e2b\u0e08.36 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 2569-07-31 1500000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 262\/120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569002046\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e17\u0e35 \u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569002046 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e17\u0e35 \u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1500000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e25\u0e49\u0e32\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e2d\u0e23\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e01\u0e48\u0e32 \u5efa\u8a2d 345\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0505569016908\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e1f\u0e39\u0e49\u0e14 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016908 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e1f\u0e39\u0e49\u0e14 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1500000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28\/118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0905569006381\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e40\u0e2d\u0e0a\u0e27\u0e32\u0e22 \u0e40\u0e2d\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006381 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e40\u0e2d\u0e0a\u0e27\u0e32\u0e22 \u0e40\u0e2d\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1500000 47640 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\/\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 (e-commerce) \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 57  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e15\u0e19\u0e2d\u0e38\u0e17\u0e34\u0e28 19 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0423569000415\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e41\u0e2d\u0e25\u0e17\u0e35 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e22\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0423569000415 \u0e2b\u0e08.\u0e0b\u0e35\u0e41\u0e2d\u0e25\u0e17\u0e35 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e22 2569-07-30 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 404\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569142435\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142435 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1500000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e44\u0e2b\u0e21\u0e1e\u0e23\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e31\u0e19\u0e2b\u0e19\u0e32\u0e27\u0e40\u0e40\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e40\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 8 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028314\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e40\u0e27\u0e48\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028314 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e40\u0e27\u0e48\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1500000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e1e\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 59\/240  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e25\u0e34\u0e25\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e30\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0485569001014\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e22\u0e4c\u0e2a \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569001014 \u0e1a\u0e08.\u0e40\u0e23\u0e22\u0e4c\u0e2a \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1500000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07 \u0e40\u0e40\u0e25\u0e30\u0e01\u0e32\u0e23\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 357\/7  \u0e16\u0e19\u0e19\u0e40\u0e1f\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e04\u0e23 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0105569142087\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e23\u0e34\u0e42\u0e21\u0e04\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142087 \u0e1a\u0e08.\u0e42\u0e21\u0e23\u0e34\u0e42\u0e21\u0e04\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 260\/21  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028161\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e32\u0e1f\u0e48\u0e32 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028161 \u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e32\u0e1f\u0e48\u0e32 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1500000 69200 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 59\/179  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e08\u0e08\u0e34\u0e42\u0e2d \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e28\u0e32\u0e25\u0e32\u0e22\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0563569000651\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2a\u0e20\u0e32\u0e20\u0e23 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0563569000651 \u0e2b\u0e08.\u0e42\u0e2a\u0e20\u0e32\u0e20\u0e23 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 2569-07-27 1500000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e22\u0e32\u0e07\u0e01\u0e49\u0e2d\u0e19\u0e16\u0e49\u0e27\u0e22 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e07\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e07\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 452  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0905569006283\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e27\u0e34\u0e15\u0e23\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006283 \u0e1a\u0e08.\u0e2a\u0e32\u0e27\u0e34\u0e15\u0e23\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1500000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569008010\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008010 \u0e2b\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-24 1500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u904b\u8f38\u30fb\u7269\u6d41 33  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e23.9\u0e0b.14\u0e41\u0e22\u0e0116 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139787\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e22\u0e2a\u0e25\u0e49\u0e32\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139787 \u0e1a\u0e08.\u0e2a\u0e32\u0e22\u0e2a\u0e25\u0e49\u0e32\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 390\/17  \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e49\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0403569003295\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 2026\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003295 \u0e2b\u0e08.\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 2026 2569-07-24 1500000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0815569002220\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35.\u0e40\u0e2d.\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e32\u0e23\u0e32\u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002220 \u0e1a\u0e08.\u0e0b\u0e35.\u0e40\u0e2d.\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e32\u0e23\u0e32\u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1500000 46632 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e44\u0e21\u0e49\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e44\u0e21\u0e49\u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e23\u0e23\u0e13 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e44\u0e21\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 117\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569013710\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e32\u0e19\u0e4c\u0e15\u0e35\u0e49 \u0e44\u0e17\u0e22 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013710 \u0e1a\u0e08.\u0e40\u0e1a\u0e32\u0e19\u0e4c\u0e15\u0e35\u0e49 \u0e44\u0e17\u0e22 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1500000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 5\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569138853\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e14\u0e35\u0e49 \u0e23\u0e35\u0e40\u0e0b\u0e47\u0e17 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138853 \u0e1a\u0e08.\u0e1a\u0e2d\u0e14\u0e35\u0e49 \u0e23\u0e35\u0e40\u0e0b\u0e47\u0e17 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1500000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 166\/23  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2a\u0e32\u0e22\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027750\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e48 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027750 \u0e1a\u0e08.\u0e21\u0e35\u0e48 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1500000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e44\u0e0b\u0e23\u0e31\u0e1b \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e2b\u0e27\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027792\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e40\u0e2d \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027792 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e40\u0e2d \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1500000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1a\u0e19\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 87\/402  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0145569004831\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35 \u0e44\u0e1a\u0e04\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004831 \u0e1a\u0e08.\u0e14\u0e35 \u0e44\u0e1a\u0e04\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1500000 82990 \u0e04\u0e49\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21-\u0e1a\u0e33\u0e23\u0e38\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 33\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0555569000637\",\"name_th\":\"\u0e1a\u0e08.688 \u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e25\u0e35\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000637 \u0e1a\u0e08.688 \u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e25\u0e35\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1500000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 688  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569138110\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138110 \u0e1a\u0e08.\u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e39\u0e18\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 8  \u0e0b\u0e2d\u0e22 \u0e0a\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2d\u0e38\u0e17\u0e34\u0e28 3 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138306\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e21\u0e48\u0e32 \u0e14\u0e2d\u0e25\u0e25\u0e48\u0e32\u0e25\u0e4c \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138306 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e21\u0e48\u0e32 \u0e14\u0e2d\u0e25\u0e25\u0e48\u0e32\u0e25\u0e4c \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1500000 47912 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/169  \u0e0b\u0e2d\u0e22 \u0e0a\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2d\u0e38\u0e17\u0e34\u0e28 10 \u0e41\u0e22\u0e01 1-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0503569005131\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e38\u0e20\u0e2a\u0e34\u0e23\u0e34 \u0e59\u0e59\u0e59\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005131 \u0e2b\u0e08.\u0e28\u0e38\u0e20\u0e2a\u0e34\u0e23\u0e34 \u0e59\u0e59\u0e59 2569-07-22 1500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 355  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0633569000774\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e0b\u0e39\u0e21\u0e342026\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32303\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32303\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000774 \u0e2b\u0e08.\u0e21\u0e32\u0e0b\u0e39\u0e21\u0e342026 2569-07-22 1500000 32303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e1a\u0e47\u0e14\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e01\u0e1b\u0e25\u0e32 \u88fd\u9020 12\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0105569137652\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e04 \u0e44\u0e2e\u0e17\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137652 \u0e1a\u0e08.\u0e1e\u0e35\u0e04 \u0e44\u0e2e\u0e17\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1500000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 (\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\/\u0e22\u0e34\u0e21) \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15 \u0e02\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e39\u0e01\u0e41\u0e25\u0e30\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19 \u82b8\u8853\u30fb\u5a2f\u697d 72\/6  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e32\u0e19\u0e09\u0e31\u0e19\u0e17\u0e4c-\u0e1a\u0e32\u0e23\u0e4c\u0e42\u0e1a\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0163569000574\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e25\u0e25\u0e32\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000574 \u0e2b\u0e08.\u0e0a\u0e25\u0e25\u0e32 2569-07-21 1500000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u5efa\u8a2d 7\/1  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0263569000174\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35 \u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e14\u0e35 \u0e01\u0e25\u0e32\u0e2a\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0263569000174 \u0e2b\u0e08.\u0e1e\u0e35 \u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e14\u0e35 \u0e01\u0e25\u0e32\u0e2a 2569-07-21 1500000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e16\u0e19\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0113569002593\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e4b\u0e41\u0e1a\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47713\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47713\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002593 \u0e2b\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e4b\u0e41\u0e1a\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 2569-07-20 1500000 47713 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 (\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22 \u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 182\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027261\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e07 \u0e42\u0e1a\u0e1a\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027261 \u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e07 \u0e42\u0e1a\u0e1a\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1500000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93\/55  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e38\u0e02-\u0e1a\u0e32\u0e07\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022332\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43309\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43309\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022332 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1500000 43309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 150\/139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0305569007501\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e27\u0e35 \u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007501 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e27\u0e35 \u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1500000 77210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e31\u0e19\u0e17\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e23\u0e16\u0e40\u0e2d\u0e17\u0e35\u0e27\u0e35 \u0e23\u0e16\u0e1a\u0e31\u0e4a\u0e01\u0e01\u0e35\u0e49\u0e2d\u0e2d\u0e1f\u0e42\u0e23\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0465569000905\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e01\u0e38\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000905 \u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e01\u0e38\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1500000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0573569002221\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e04\u0e14\u0e39\u0e42\u0e2e\u0e21\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002221 \u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e04\u0e14\u0e39\u0e42\u0e2e\u0e21 2569-07-19 1500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 265  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e48\u0e32\u0e40\u0e2b\u0e35\u0e22\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0773569000421\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e19\u0e01\u0e34\u0e08 \u0e40\u0e08\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0773569000421 \u0e2b\u0e08.\u0e40\u0e08\u0e19\u0e01\u0e34\u0e08 \u0e40\u0e08\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 2569-07-17 1500000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1\/47  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0113569002542\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e2d\u0e07\u0e0a\u0e39\u0e43\u0e2a\u0e48\u0e2a\u0e1a\u0e32\u0e22\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002542 \u0e2b\u0e08.\u0e25\u0e2d\u0e07\u0e0a\u0e39\u0e43\u0e2a\u0e48\u0e2a\u0e1a\u0e32\u0e22 2569-07-16 1500000 47712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e2a\u0e15\u0e23\u0e35 \u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01\u0e2d\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e27\u0e31\u0e15\u0e16\u0e38\u0e43\u0e0a\u0e49\u0e41\u0e17\u0e19 \u0e2b\u0e19\u0e31\u0e07 \u0e22\u0e32\u0e07 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e2b\u0e23\u0e37\u0e2d \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 182\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0163569000566\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e31\u0e19\u0e21\u0e35\u0e14\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000566 \u0e2b\u0e08.\u0e27\u0e31\u0e19\u0e21\u0e35\u0e14\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 2569-07-16 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 89\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0473569000938\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22 2520\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000938 \u0e2b\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22 2520 2569-07-16 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 324  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004983\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e2d\u0e25 \u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 \u0e23\u0e16\u0e40\u0e0a\u0e48\u0e32\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004983 \u0e2b\u0e08.\u0e2d\u0e2d\u0e25 \u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 \u0e23\u0e16\u0e40\u0e0a\u0e48\u0e32 2569-07-16 1500000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e16\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 145\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0805569002742\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002742 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1500000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e2a\u0e34\u0e19 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e27\u0e07\u0e16\u0e32\u0e21\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e2b\u0e19\u0e35\u0e49\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2b\u0e19\u0e35\u0e49\u0e01\u0e48\u0e2d\u0e19\u0e1f\u0e49\u0e2d\u0e07 \u0e2b\u0e19\u0e35\u0e49\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1f\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35   \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 129\/630  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e19\u0e14\u0e35\u0e42\u0e06\u0e29\u0e34\u0e15\u0e01\u0e38\u0e25\u0e1e\u0e23 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0935569000838\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e17\u0e23 \u0e15\u0e30\u0e42\u0e2b\u0e21\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000838 \u0e1a\u0e08.\u0e0a\u0e32\u0e17\u0e23 \u0e15\u0e30\u0e42\u0e2b\u0e21\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1500000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e07\u0e0a\u0e32 \u0e02\u0e32\u0e22\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e0a\u0e32\u0e17\u0e23\u0e15\u0e30\u0e42\u0e2b\u0e21\u0e14 \u0e41\u0e25\u0e30 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e07\u0e0a\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0105569133720\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e22\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07 5 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133720 \u0e1a\u0e08.\u0e1a\u0e35 \u0e22\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07 5 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e04\u0e38\u0e01\u0e01\u0e35\u0e49 \u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e41\u0e0b\u0e19\u0e27\u0e34\u0e0a \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 265  \u0e0b\u0e2d\u0e22 \u0e40\u0e22\u0e47\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e28 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0215569009459\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009459 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1500000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e2d\u0e1a\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e31\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e1a\u0e1c\u0e49\u0e32 \u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 1\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0773569000404\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e22\u0e1e\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e22\u0e19\u0e15\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0773569000404 \u0e2b\u0e08.\u0e27\u0e32\u0e22\u0e1e\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e22\u0e19\u0e15\u0e4c 2569-07-15 1500000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e2a\u0e32\u0e21\u0e25\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 502\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0105569133011\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35. \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133011 \u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35. \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1500000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u4e0d\u52d5\u7523 212  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0505569015880\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19 \u0e21\u0e32\u0e0b\u0e2a\u0e32\u0e08 \u0e2d\u0e30\u0e40\u0e17\u0e25\u0e34\u0e40\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015880 \u0e1a\u0e08.\u0e40\u0e0b\u0e19 \u0e21\u0e32\u0e0b\u0e2a\u0e32\u0e08 \u0e2d\u0e30\u0e40\u0e17\u0e25\u0e34\u0e40\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1500000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2a\u0e1b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 203\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0725569002107\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e1f\u0e25\u0e39\u0e1b\u0e2a\u0e4c \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002107 \u0e1a\u0e08.\u0e40\u0e14\u0e1f\u0e25\u0e39\u0e1b\u0e2a\u0e4c \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1500000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 (it)\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (digital transformation) \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0925569001044\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e38\u0e0a\u0e34\u0e15 \u0e2a.\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33151\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33151\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001044 \u0e1a\u0e08.\u0e2d\u0e19\u0e38\u0e0a\u0e34\u0e15 \u0e2a.\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1500000 33151 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e40\u0e23\u0e37\u0e2d \u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e23\u0e37\u0e2d \u0e15\u0e48\u0e2d\u0e40\u0e23\u0e37\u0e2d \u0e15\u0e48\u0e2d\u0e41\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u88fd\u9020 129\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0303569002699\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 1988\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002699 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 1988 2569-07-10 1500000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e02\u0e38\u0e14 \u0e25\u0e2d\u0e01 \u0e04\u0e39 \u0e04\u0e25\u0e2d\u0e07 \u0e2b\u0e19\u0e2d\u0e07 \u0e1a\u0e36\u0e07 \u0e2a\u0e23\u0e30\u0e19\u0e49\u0e33 \u0e16\u0e21\u0e17\u0e35\u0e48 \u0e1b\u0e23\u0e31\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u5efa\u8a2d 17  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e2b\u0e31\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0133569002330\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04 \u0e27\u0e32\u0e22 \u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002330 \u0e2b\u0e08.\u0e40\u0e04 \u0e27\u0e32\u0e22 \u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04 2569-07-09 1500000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002348\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e31\u0e19\u0e22\u0e32 \u0e42\u0e1b\u0e23\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002348 \u0e2b\u0e08.\u0e01\u0e31\u0e19\u0e22\u0e32 \u0e42\u0e1b\u0e23\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-09 1500000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0305569007102\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e17\u0e34\u0e0a\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007102 \u0e1a\u0e08.\u0e1e\u0e23\u0e17\u0e34\u0e0a\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e19\u0e2d\u0e07  \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 (\u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e40\u0e09\u0e1e\u0e32\u0e30) \u5efa\u8a2d 333\/801  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e13\u0e32\u0e2a\u0e23\u0e32 \u0e2d\u0e04\u0e27\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0473569000903\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e1e\u0e23\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 1988\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000903 \u0e2b\u0e08.\u0e41\u0e1e\u0e23\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 1988 2569-07-09 1500000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 201  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e15\u0e32\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004525\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e1e\u0e23\u0e23\u0e13\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004525 \u0e2b\u0e08.\u0e1e\u0e23\u0e1e\u0e23\u0e23\u0e13\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 2569-07-09 1500000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e28\u0e29\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015472\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46614\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46614\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015472 \u0e1a\u0e08.\u0e28\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1500000 46614 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e2d\u0e2a\u0e1f\u0e31\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0653569001088\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19 \u0e23\u0e34\u0e0a\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001088 \u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19 \u0e23\u0e34\u0e0a 2569-07-09 1500000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0933569000291\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e39\u0e01\u0e41\u0e1d\u0e14 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0933569000291 \u0e2b\u0e08.\u0e25\u0e39\u0e01\u0e41\u0e1d\u0e14 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2569-07-09 1500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0393569000343\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e23\u0e34\u0e19\u0e17\u0e23 168\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000343 \u0e2b\u0e08.\u0e27\u0e23\u0e34\u0e19\u0e17\u0e23 168 2569-07-08 1500000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 249  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0165569001513\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001513 \u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1500000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e48\u0e2d\u0e21 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0115569022341\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e25\u0e0b\u0e35 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022341 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e25\u0e0b\u0e35 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1500000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 118\/120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569035492\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e23\u0e1f \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035492 \u0e1a\u0e08.\u0e40\u0e1a\u0e23\u0e1f \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1500000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e36\u0e07-\u0e2b\u0e19\u0e2d\u0e07\u0e01\u0e32\u0e19\u0e49\u0e33 1 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e36\u0e07-\u0e2b\u0e19\u0e2d\u0e07\u0e01\u0e32\u0e19\u0e49\u0e33 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007005\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e38\u0e23\u0e35\u0e1e\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007005 \u0e1a\u0e08.\u0e08\u0e38\u0e23\u0e35\u0e1e\u0e23\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1500000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 413  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0653569001037\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e2d\u0e17\u0e2a\u0e32\u0e21\u0e2a\u0e2d\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001037 \u0e2b\u0e08.\u0e14\u0e2d\u0e17\u0e2a\u0e32\u0e21\u0e2a\u0e2d\u0e07 2569-07-06 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 800\/23  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e44\u0e15\u0e23\u0e42\u0e25\u0e01\u0e19\u0e32\u0e23\u0e16 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0245569003612\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003612 \u0e1a\u0e08.\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0473569000873\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 2026\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000873 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 2026 2569-07-03 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 348  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004347\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004347 \u0e2b\u0e08.\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 2569-07-03 1500000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e28\u0e29\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29,\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01,\u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 297  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0103569006793\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35.\u0e40\u0e04.\u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006793 \u0e2b\u0e08.\u0e17\u0e35.\u0e40\u0e04.\u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25 2569-07-02 1500000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 316,318  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006831\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006831 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 2569-07-02 1500000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e42\u0e23\u0e07\u0e2a\u0e35 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e38\u0e23\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 205  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125271\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e35\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125271 \u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e35\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1500000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 26  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0495569000514\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e23\u0e34\u0e0a\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000514 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e23\u0e34\u0e0a\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1500000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e23\u0e35\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e1d\u0e49\u0e32 \u0e01\u0e23\u0e30 \u0e2b\u0e19\u0e49\u0e32\u0e43\u0e2a \u533b\u7642\u30fb\u798f\u7949 122\/4  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e27\u0e34\u0e18\u0e2a\u0e38\u0e23\u0e01\u0e32\u0e23 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569006483\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e44\u0e19\u0e19\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006483 \u0e2b\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e44\u0e19\u0e19\u0e4c 2569-07-01 1500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 310\/320  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e20\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006742\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e25\u0e32\u0e2a\u0e0b\u0e35\u0e48 \u0e0a\u0e34\u0e04\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006742 \u0e2b\u0e08.\u0e04\u0e25\u0e32\u0e2a\u0e0b\u0e35\u0e48 \u0e0a\u0e34\u0e04 2569-07-01 1500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 310\/320  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e20\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124089\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e27\u0e4c\u0e40\u0e22\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c (\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124089 \u0e1a\u0e08.\u0e25\u0e2d\u0e27\u0e4c\u0e40\u0e22\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c (\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1500000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e02\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27\u0e42\u0e17\u0e29 \u0e1f\u0e49\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e04\u0e14\u0e35 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e48\u0e07 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e0d\u0e32 \u0e17\u0e32\u0e07\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e04\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e35\u0e01\u0e1d\u0e48\u0e32\u0e22\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e16\u0e2d\u0e19\u0e1f\u0e49\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e13\u0e35\u0e1b\u0e23\u0e30\u0e19\u0e2d\u0e21\u0e22\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e2a\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e18\u0e23\u0e13\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e0e\u0e35\u0e01\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e13\u0e32\u0e04\u0e14\u0e35\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e23\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e2d\u0e31\u0e19\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e48\u0e2d\u0e04\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e04\u0e14\u0e35\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e15\u0e48\u0e2d\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e28\u0e32\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e02\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e2d\u0e01\u0e40\u0e02\u0e15\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e42\u0e15\u0e15\u0e38\u0e25\u0e32\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 582\/97  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1e\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21-\u0e1a\u0e32\u0e07\u0e41\u0e04 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0223569000298\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35 \u0e21\u0e34\u0e19\u0e34\u0e21\u0e2d\u0e25\u0e25\u0e34\u0e2a\u0e15\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000298 \u0e2b\u0e08.\u0e17\u0e35 \u0e21\u0e34\u0e19\u0e34\u0e21\u0e2d\u0e25\u0e25\u0e34\u0e2a\u0e15\u0e4c 2569-07-01 1500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0223569000310\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e07\u0e40\u0e08\u0e25\u0e34\u0e04\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000310 \u0e2b\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e07\u0e40\u0e08\u0e25\u0e34\u0e04 2569-07-01 1500000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0643569000499\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e1a\u0e35 \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1500000,\"capital_display\":\"1,500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0643569000499 \u0e2b\u0e08.\u0e40\u0e04\u0e1a\u0e35 \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-01 1500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 340\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0905569005767\",\"name_th\":\"\u0e1a\u0e08.22 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1400000,\"capital_display\":\"1,400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005767 \u0e1a\u0e08.22 \u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1400000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e14 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 20,22  \u0e16\u0e19\u0e19\u0e0a\u0e32\u0e22\u0e40\u0e02\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0523569001372\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e1f\u0e39\u0e14\u0e2a\u0e4c 2026\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1400000,\"capital_display\":\"1,400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001372 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e1f\u0e39\u0e14\u0e2a\u0e4c 2026 2569-07-08 1400000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0603569001649\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e35\u0e19\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1300000,\"capital_display\":\"1,300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001649 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e35\u0e19\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-20 1300000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 119\/961  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0203569002878\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e32\u0e22\u0e31\u0e19 \u0e40\u0e27\u0e17 \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c  2569\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1245000,\"capital_display\":\"1,245,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002878 \u0e2b\u0e08.\u0e2a\u0e32\u0e22\u0e31\u0e19 \u0e40\u0e27\u0e17 \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c  2569 2569-07-08 1245000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22          \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0503569005271\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e41\u0e04\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01121\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01121\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005271 \u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e41\u0e04\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-25 1200000 01121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569137954\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137954 \u0e1a\u0e08.\u0e2b\u0e07\u0e2a\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1200000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e40\u0e40\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e07\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 995  \u0e16\u0e19\u0e19\u0e17\u0e23\u0e07\u0e27\u0e32\u0e14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138331\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b   \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138331 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b   \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1200000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 869  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e44\u0e1e\u0e25\u0e34\u0e19 \u0e1a\u0e34\u0e2a\u0e2a\u0e34\u0e40\u0e19\u0e2a \u0e1e\u0e2d\u0e22\u0e17\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2-1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137326\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e08\u0e35 \u0e0a\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137326 \u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e08\u0e35 \u0e0a\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1200000 66191 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 581  \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134165\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e41\u0e23\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134165 \u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e41\u0e23\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1200000 10751 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e17\u0e30\u0e40\u0e25 \u88fd\u9020 252\/25  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07112 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0465569000875\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e1a\u0e34\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000875 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e1a\u0e34\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1200000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e42\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 27  \u0e16\u0e19\u0e19\u0e42\u0e2a\u0e21\u0e1e\u0e30\u0e21\u0e34\u0e15\u0e23 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0905569005635\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e33\u0e17\u0e35\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005635 \u0e1a\u0e08.\u0e19\u0e33\u0e17\u0e35\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1200000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 15\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 1 (\u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 6) \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569130135\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e1a\u0e35\u0e1e\u0e35\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130135 \u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e1a\u0e35\u0e1e\u0e35\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1200000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e01\u0e25\u0e37\u0e2d\u0e41\u0e23\u0e48\u0e1c\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128271\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e41\u0e25\u0e0a \u0e42\u0e23\u0e2a\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128271 \u0e1a\u0e08.\u0e2a\u0e41\u0e25\u0e0a \u0e42\u0e23\u0e2a\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1200000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 62\/17  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e32\u0e23\u0e32\u0e19\u0e35 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124976\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11049\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11049\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124976 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1200000 11049 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 1\/41  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1940 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0573569002000\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1a\u0e2a\u0e17\u0e4c \u0e04\u0e31\u0e1e \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1200000,\"capital_display\":\"1,200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002000 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1a\u0e2a\u0e17\u0e4c \u0e04\u0e31\u0e1e \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 2569-07-02 1200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 346  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0903569001841\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e32\u0e21\u0e2a\u0e2b\u0e32\u0e22\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e49\u0e04\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001841 \u0e2b\u0e08.\u0e2a\u0e32\u0e21\u0e2a\u0e2b\u0e32\u0e22\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e49\u0e04 2569-07-28 1100000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001859\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e2a 78 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001859 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e2a 78 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-28 1100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19  \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07  \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u5efa\u8a2d 137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001867\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2d\u0e40\u0e04\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e32\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001867 \u0e2b\u0e08.\u0e42\u0e2d\u0e40\u0e04\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e32\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22 2569-07-28 1100000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e15\u0e32\u0e01\u0e41\u0e2b\u0e49\u0e07  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001875\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d \u0e2d\u0e32\u0e23\u0e4c 99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001875 \u0e2b\u0e08.\u0e40\u0e2d \u0e2d\u0e32\u0e23\u0e4c 99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-28 1100000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e2b\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e21\u0e32\u0e01  \u0e40\u0e0a\u0e48\u0e19 \u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a \u0e41\u0e1b\u0e49\u0e07 \u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e17\u0e23\u0e32\u0e22 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e43\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u904b\u8f38\u30fb\u7269\u6d41 73\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569140149\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140149 \u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1100000 46411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e49\u0e32\u0e21\u0e49\u0e27\u0e19 \u0e1c\u0e49\u0e32\u0e17\u0e2d \u0e1c\u0e49\u0e32\u0e1c\u0e37\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93\/433  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0845569010672\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010672 \u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 102\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0643569000529\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e32\u0e19\u0e32\u0e19\u0e48\u0e32 \u0e0b\u0e31\u0e19\u0e44\u0e0a\u0e19\u0e4c\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10302\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10302\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0643569000529 \u0e2b\u0e08.\u0e1a\u0e32\u0e19\u0e32\u0e19\u0e48\u0e32 \u0e0b\u0e31\u0e19\u0e44\u0e0a\u0e19\u0e4c 2569-07-18 1100000 10302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e16\u0e19\u0e2d\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e01\u0e25\u0e49\u0e27\u0e22\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e01\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0103569007323\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e23\u0e2a\u0e0b\u0e32\u0e40\u0e23\u0e35\u0e22\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32904\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32904\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007323 \u0e2b\u0e08.\u0e42\u0e23\u0e2a\u0e0b\u0e32\u0e40\u0e23\u0e35\u0e22 2569-07-10 1100000 32904 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e49\u0e27\u0e22\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e42\u0e2d\u0e01\u0e32\u0e2a \u88fd\u9020 42   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 42 \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 25 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0845569010257\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010257 \u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1100000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u4e0d\u52d5\u7523 35\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0903569001549\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e39\u0e42\u0e19\u0e48\u0e42\u0e21\u0e40\u0e19\u0e15\u0e49\u0e32\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001549 \u0e2b\u0e08.\u0e08\u0e39\u0e42\u0e19\u0e48\u0e42\u0e21\u0e40\u0e19\u0e15\u0e49\u0e32 2569-07-10 1100000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139  \u0e0b\u0e2d\u0e22 8\/2 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005571\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e15\u0e2e\u0e31\u0e1a2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005571 \u0e1a\u0e08.\u0e1f\u0e34\u0e15\u0e2e\u0e31\u0e1a2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1100000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u82b8\u8853\u30fb\u5a2f\u697d 87  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07 \u0e23.6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0363569000815\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1100000,\"capital_display\":\"1,100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000815 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c 2569-07-01 1100000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e43\u0e19\u0e24\u0e14\u0e39\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e24\u0e14\u0e39 \u8fb2\u6797\u6c34\u7523 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0415569003793\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e14\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1010000,\"capital_display\":\"1,010,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003793 \u0e1a\u0e08.\u0e22\u0e39\u0e14\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1010000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 197  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569005327\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e42\u0e22\u0e18\u0e32\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000001,\"capital_display\":\"1,000,001 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005327 \u0e2b\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e42\u0e22\u0e18\u0e32 2569-07-30 1000001 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 44\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569005301\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000001,\"capital_display\":\"1,000,001 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005301 \u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-29 1000001 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569140122\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e41\u0e21\u0e0a \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000001,\"capital_display\":\"1,000,001 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140122 \u0e1a\u0e08.\u0e2a\u0e41\u0e21\u0e0a \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000001 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2b\u0e49\u0e2d\u0e07\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u82b8\u8853\u30fb\u5a2f\u697d 437\/687  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569008206\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e27\u0e19\u0e32\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008206 \u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e27\u0e19\u0e32 2569-07-31 1000000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e39\u0e0a\u0e34 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e38\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u88fd\u9020 54  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142788\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142788 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46101 \u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1e\u0e37\u0e0a\u0e1e\u0e23\u0e23\u0e13\u0e44\u0e21\u0e49 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e01 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49 \u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2823\/3  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142796\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e40\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47911\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47911\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142796 \u0e1a\u0e08.\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e40\u0e23\u0e40\u0e27\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47911 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168  \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 0013 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142800\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e23\u0e1f\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142800 \u0e1a\u0e08.\u0e44\u0e14\u0e23\u0e1f\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 550\/93  \u0e16\u0e19\u0e19\u0e2d\u0e42\u0e28\u0e01-\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142818\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e40\u0e2d\u0e47\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e4c \u0e2d\u0e2d\u0e40\u0e17\u0e19\u0e17\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142818 \u0e1a\u0e08.\u0e17\u0e39\u0e40\u0e2d\u0e47\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e4c \u0e2d\u0e2d\u0e40\u0e17\u0e19\u0e17\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/253  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e40\u0e1e\u0e25\u0e2a \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 2 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 174 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142834\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142834 \u0e1a\u0e08.\u0e25\u0e39\u0e40\u0e0b\u0e19\u0e15\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u4e0d\u52d5\u7523 546  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e04\u0e19\u0e27\u0e32\u0e2a \u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142877\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142877 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 145\/18-19  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e07\u0e29\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b508\/4 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142885\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1e\u0e27\u0e32 \u0e41\u0e1e\u0e23\u0e27\u0e32 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142885 \u0e1a\u0e08.\u0e42\u0e1e\u0e27\u0e32 \u0e41\u0e1e\u0e23\u0e27\u0e32 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e1c\u0e49\u0e32\u0e19\u0e38\u0e48\u0e21 \u0e1b\u0e32\u0e01\u0e01\u0e32\u0e02\u0e08\u0e31\u0e14\u0e04\u0e23\u0e32\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e0b\u0e23\u0e31\u0e48\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32 \u0e2a\u0e1a\u0e39\u0e48 \u0e41\u0e25\u0e30\u0e41\u0e0a\u0e21\u0e1e\u0e39 (\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/118  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e4c\u0e25\u0e14\u0e32 \u0e17\u0e32\u0e07\u0e14\u0e48\u0e27\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e34 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e23\u0e30\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142893\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e39\u0e23\u0e19\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142893 \u0e1a\u0e08.\u0e1b\u0e39\u0e23\u0e19\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e14\u0e49\u0e32\u0e19\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 1249\/213  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142923\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e21\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142923 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e21\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e15\u0e33\u0e23\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u6559\u80b2 40\/1 \u0e15\u0e23\u0e2d\u0e01\u0e27\u0e31\u0e14\u0e23\u0e32\u0e0a\u0e27\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c 7  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142940\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142940 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 18\/31  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142958\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 1991 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142958 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 1991 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 14\/107  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142991\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e1e\u0e47\u0e0d\u0e2a\u0e39\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142991 \u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e1e\u0e47\u0e0d\u0e2a\u0e39\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e39\u0e17 \u88fd\u9020 1070\/3  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143032\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e32\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143032 \u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e32\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 221  \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143041\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143041 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 9\/33  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143067\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143067 \u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 387  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143083\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b  168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143083 \u0e1a\u0e08.\u0e40\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b  168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32  \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/30  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 1\/10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143091\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25  \u0e0b\u0e2d\u0e1f\u0e15\u0e4c  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143091 \u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25  \u0e0b\u0e2d\u0e1f\u0e15\u0e4c  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e42\u0e1b\u0e23\u0e40\u0e40\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e40\u0e40\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e40\u0e01\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e40\u0e40\u0e27\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e40\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2e\u0e32\u0e23\u0e4c\u0e15\u0e41\u0e27\u0e23\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e40\u0e40\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 21  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143105\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e19\u0e18\u0e34\u0e1b \u0e18\u0e32\u0e27\u0e34\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143105 \u0e1a\u0e08.\u0e0a\u0e34\u0e19\u0e18\u0e34\u0e1b \u0e18\u0e32\u0e27\u0e34\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 86201 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e27\u0e0a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19\u0e1e\u0e31\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e49\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e2d\u0e07  \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e43\u0e19 \u533b\u7642\u30fb\u798f\u7949 5\/2  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143121\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e04\u0e32 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143121 \u0e1a\u0e08.\u0e0b\u0e34\u0e04\u0e32 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d \u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22 \u0e42\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23 \u0e0a\u0e37\u0e48\u0e2d\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u91d1\u878d\u30fb\u4fdd\u967a 122\/2-3  \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143148\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e40\u0e25\u0e47\u0e15 \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52213\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52213\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143148 \u0e1a\u0e08.\u0e27\u0e32\u0e40\u0e25\u0e47\u0e15 \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 52213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e14\u0e23\u0e16 (valet parking service) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19            \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 188\/359  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e213 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 30 \u0e41\u0e22\u0e01 10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143156\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24202\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24202\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143156 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 24202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e21\u0e38\u0e49\u0e07\u0e25\u0e27\u0e14 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e41\u0e1c\u0e48\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e09\u0e19\u0e27\u0e19 \u0e41\u0e1c\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1d\u0e49\u0e32\u0e40\u0e1e\u0e14\u0e32\u0e19 \u0e1c\u0e19\u0e31\u0e07\u0e40\u0e1a\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 466\/10  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 20 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143172\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e0b\u0e4c\u0e17\u0e35\u0e19 \u0e21\u0e34\u0e40\u0e23\u0e2d\u0e38 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143172 \u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e0b\u0e4c\u0e17\u0e35\u0e19 \u0e21\u0e34\u0e40\u0e23\u0e2d\u0e38 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85\/253  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 79 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143181\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143181 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e23\u0e30\u0e21\u0e32\u0e14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143199\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e30\u0e14\u0e34\u0e27\u0e48\u0e32 \u0e21\u0e39\u0e25\u0e32\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143199 \u0e1a\u0e08.\u0e21\u0e30\u0e14\u0e34\u0e27\u0e48\u0e32 \u0e21\u0e39\u0e25\u0e32\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e35\u0e27\u0e34\u0e27 \u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d \u0e41\u0e25\u0e30\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/21  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e1a\u0e39\u0e40\u0e25\u0e2d\u0e27\u0e32\u0e23\u0e4c\u0e14 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 11\/5 \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143202\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143202 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e25\u0e49\u0e32\u0e07\u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e02\u0e31\u0e14\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143245\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e27\u0e25 \u0e40\u0e19\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143245 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e27\u0e25 \u0e40\u0e19\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 72101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e17\u0e14\u0e25\u0e2d\u0e07 \u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e41\u0e1b\u0e25\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e46\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 399\/4  \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143253\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52241\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52241\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143253 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 52241 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 19\/93  \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143318\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143318 \u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 171\/189  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 174 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143351\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e42\u0e19\u0e27\u0e4c\u0e17\u0e34\u0e04\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79909\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79909\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143351 \u0e1a\u0e08.\u0e2a\u0e42\u0e19\u0e27\u0e4c\u0e17\u0e34\u0e04\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 79909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e31\u0e15\u0e23\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e1f\u0e19\u0e21\u0e34\u0e15\u0e15\u0e34\u0e49\u0e07 (fan meeting) \u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e14\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 104  \u0e0b\u0e2d\u0e22 \u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143377\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e25\u0e31\u0e04\u0e28\u0e31\u0e01\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143377 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e25\u0e31\u0e04\u0e28\u0e31\u0e01\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e34\u0e14\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 1231-1233  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143385\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e21 \u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143385 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e21 \u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 93112 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 2  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 79 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143393\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e13\u0e23\u0e38\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143393 \u0e1a\u0e08.\u0e23\u0e31\u0e13\u0e23\u0e38\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e.\u0e23.\u0e1a. \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52\/1  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e14\u0e34\u0e1e\u0e31\u0e17\u0e18\u0e4c 17 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025200\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e13\u0e38\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025200 \u0e1a\u0e08.\u0e20\u0e32\u0e13\u0e38\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 88\/296  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1f\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e49\u0e32 12 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025218\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025218 \u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 584\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025226\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e04 3569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025226 \u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e04 3569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 168\/149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025234\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e17\u0e35\u0e08\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025234 \u0e1a\u0e08.\u0e08\u0e35\u0e17\u0e35\u0e08\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e1a\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48  \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e43\u0e1a\u0e15\u0e23\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 99  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e2d\u0e40\u0e2d\u0e2a\u0e0b\u0e35  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 411 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e01\u0e34\u0e48\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025251\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e34\u0e1f\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025251 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e17\u0e34\u0e1f\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e01\u0e25 iso and food safety \u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e01\u0e25 iso and food safety (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/216  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e31\u0e2a\u0e42\u0e15\u0e49\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025285\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025285 \u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e21\u0e27\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e21\u0e27\u0e01\u0e01\u0e31\u0e19\u0e19\u0e47\u0e2d\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 444\/41  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025293\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025293 \u0e1a\u0e08.\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 145\/148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569028438\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028438 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e1a\u0e31\u0e1a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 73  \u0e0b\u0e2d\u0e22 \u0e40\u0e23\u0e27\u0e14\u0e35 35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028446\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e27 \u0e42\u0e1b\u0e23\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028446 \u0e1a\u0e08.\u0e1a\u0e31\u0e27 \u0e42\u0e1b\u0e23\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e2a\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 55\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028454\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e41\u0e21\u0e19\u0e14\u0e49\u0e32 \u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028454 \u0e1a\u0e08.\u0e2d\u0e41\u0e21\u0e19\u0e14\u0e49\u0e32 \u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46414 \u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028462\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e19\u0e15\u0e49\u0e32\u0e1a\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028462 \u0e1a\u0e08.\u0e0b\u0e32\u0e19\u0e15\u0e49\u0e32\u0e1a\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c(e-commerce) \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2d\u0e31\u0e19\u0e21\u0e34\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/103  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e32\u0e0b\u0e48\u0e32 \u0e40\u0e1e\u0e23\u0e2a\u0e42\u0e15\u0e49 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028471\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e4c\u0e21\u0e34\u0e2a \u0e2d\u0e35\u0e40\u0e25\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028471 \u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e4c\u0e21\u0e34\u0e2a \u0e2d\u0e35\u0e40\u0e25\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 56101 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23\/\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 (restaurants activities) \u5bbf\u6cca\u30fb\u98f2\u98df 20\/383  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028489\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e25\u0e25\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32402\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32402\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028489 \u0e1a\u0e08.\u0e14\u0e2d\u0e25\u0e25\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 32402 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e34\u0e1f\u0e17\u0e4c\u0e0a\u0e47\u0e2d\u0e1b \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e21\u0e37\u0e2d\u0e15\u0e38\u0e4a\u0e01\u0e15\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c diy\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 88\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028497\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96305\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96305\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028497 \u0e1a\u0e08.\u0e44\u0e2d\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 96305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e1a\u0e44\u0e2d\u0e19\u0e4d\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e1f\u0e34\u0e19\u0e41\u0e25\u0e19\u0e14\u0e4c (\u0e0b\u0e32\u0e27\u0e19\u0e48\u0e32) \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e0a\u0e48 \u0e19\u0e4d\u0e49\u0e32\u0e40\u0e22\u0e47\u0e19(ice bath) \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19(contrast therapy) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 337\/141  \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028501\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e14\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028501 \u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e14\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e49\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 337\/172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002682\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e34\u0e27 \u0e42\u0e0a\u0e04\u0e04\u0e33\u0e20\u0e35\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002682 \u0e2b\u0e08.\u0e19\u0e34\u0e27 \u0e42\u0e0a\u0e04\u0e04\u0e33\u0e20\u0e35\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-31 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 4\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023487\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e2d\u0e04\u0e42\u0e04\u0e48 \u0e42\u0e2e\u0e40\u0e17\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023487 \u0e1a\u0e08. \u0e40\u0e2d\u0e04\u0e42\u0e04\u0e48 \u0e42\u0e2e\u0e40\u0e17\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023495\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e01\u0e2a\u0e4c\u0e2d\u0e31\u0e1e \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023495 \u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e01\u0e2a\u0e4c\u0e2d\u0e31\u0e1e \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/2029  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023517\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e0d\u0e28\u0e34\u0e25\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023517 \u0e1a\u0e08.\u0e2d\u0e31\u0e0d\u0e28\u0e34\u0e25\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u88fd\u9020 111\/145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023541\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e01\u0e39\u0e4a\u0e14\u0e44\u0e25\u0e1f\u0e4c\u0e01\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023541 \u0e1a\u0e08.\u0e22\u0e39\u0e01\u0e39\u0e4a\u0e14\u0e44\u0e25\u0e1f\u0e4c\u0e01\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e14\u0e32\u0e23\u0e32\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e38\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2d\u0e34\u0e19\u0e1f\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e19\u0e31\u0e01\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 4\/73  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 34\/1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023550\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023550 \u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 17\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004971\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004971 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2b\u0e31\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e0d\u52d5\u7523 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0185569000525\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e28\u0e34\u0e23\u0e34\u0e42\u0e01\u0e25\u0e14\u0e4c (\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0185569000525 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e28\u0e34\u0e23\u0e34\u0e42\u0e01\u0e25\u0e14\u0e4c (\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/9  \u0e16\u0e19\u0e19\u0e27\u0e07\u0e29\u0e4c\u0e42\u0e15 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0195569002706\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e35\u0e48 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002706 \u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e35\u0e48 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003343\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35 \u0e1e\u0e32\u0e23\u0e34\u0e01 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003343 \u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35 \u0e1e\u0e32\u0e23\u0e34\u0e01 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 2569-07-31 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e40\u0e0a\u0e34\u0e14 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e16\u0e48\u0e32\u0e22\u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 459\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003378\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e1e\u0e35 1977\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003378 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e1e\u0e35 1977 2569-07-31 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039544\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e0a\u0e31\u0e22\u0e1e\u0e25  \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039544 \u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e0a\u0e31\u0e22\u0e1e\u0e25  \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46591 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e43\u0e19\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 152\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2b\u0e49\u0e27\u0e22\u0e01\u0e30\u0e1b\u0e34 17 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039595\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e32\u0e25\u0e32 \u0e40\u0e2d\u0e40\u0e25\u0e41\u0e01\u0e19\u0e0b\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039595 \u0e1a\u0e08.\u0e17\u0e32\u0e25\u0e32 \u0e40\u0e2d\u0e40\u0e25\u0e41\u0e01\u0e19\u0e0b\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 81210 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14  \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07  \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 101\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039625\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e08\u0e34\u0e49\u0e07\u0e25\u0e35\u0e48 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039625 \u0e1a\u0e08. \u0e40\u0e08\u0e34\u0e49\u0e07\u0e25\u0e35\u0e48 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 22299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e09\u0e35\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e09\u0e35\u0e14\u0e17\u0e38\u0e01\u0e23\u0e30\u0e1a\u0e1a \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e09\u0e35\u0e14\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e42\u0e21\u0e25\u0e4c\u0e14 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e42\u0e25\u0e2b\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 265\/60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039633\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e19\u0e32\u0e40\u0e23\u0e34\u0e01 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039633 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e19\u0e32\u0e40\u0e23\u0e34\u0e01 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039676\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e04 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47221\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47221\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039676 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e04 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039684\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039684 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 58202 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c (software & solutions) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u60c5\u5831\u901a\u4fe1\u30fbit 98\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569010074\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e42\u0e21\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e19\u0e40\u0e1e\u0e47\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010074 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e42\u0e21\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e19\u0e40\u0e1e\u0e47\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 75\/96,75\/97  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002411\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e25\u0e32\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002411 \u0e1a\u0e08.\u0e1b\u0e25\u0e32\u0e22\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 7\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569004104\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e22\u0e48\u0e07\u0e2b\u0e21\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004104 \u0e1a\u0e08.\u0e2b\u0e22\u0e48\u0e07\u0e2b\u0e21\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u5efa\u8a2d 47\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569004112\",\"name_th\":\"\u0e1a\u0e08.\u0e0d\u0e32\u0e14\u0e32 1995 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004112 \u0e1a\u0e08.\u0e0d\u0e32\u0e14\u0e32 1995 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 22\/198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569004121\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004121 \u0e1a\u0e08.\u0e1e\u0e35\u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 18119 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 95\/114  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e1f \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1b\u0e30\u0e01\u0e07 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569007781\",\"name_th\":\"\u0e1a\u0e08. \u0e04\u0e34\u0e27\u0e1b\u0e34\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007781 \u0e1a\u0e08. \u0e04\u0e34\u0e27\u0e1b\u0e34\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 225  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e25\u0e2d\u0e07\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007790\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007790 \u0e1a\u0e08.\u0e14\u0e38\u0e2a\u0e34\u0e15 \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e33\u0e21\u0e32\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007803\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e1b\u0e42\u0e15 \u0e42\u0e21\u0e42\u0e15\u0e30 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e31\u0e2a\u0e15\u0e31\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007803 \u0e1a\u0e08.\u0e42\u0e04\u0e1b\u0e42\u0e15 \u0e42\u0e21\u0e42\u0e15\u0e30 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e31\u0e2a\u0e15\u0e31\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e41\u0e1f\u0e23\u0e34\u0e48\u0e07 \u0e1d\u0e32\u0e04\u0e23\u0e2d\u0e1a \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01 \u0e1a\u0e31\u0e07\u0e42\u0e04\u0e25\u0e19 \u0e0a\u0e34\u0e25\u0e14\u0e4c\u0e1a\u0e31\u0e07\u0e25\u0e21 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 abs \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e32\u0e22\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e44\u0e1f\u0e2b\u0e19\u0e49\u0e32 \u0e44\u0e1f\u0e17\u0e49\u0e32\u0e22 \u0e44\u0e1f\u0e40\u0e25\u0e35\u0e49\u0e22\u0e27 \u0e44\u0e1f\u0e40\u0e1a\u0e23\u0e01 \u0e44\u0e1f\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e44\u0e1f\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16 \u0e2b\u0e25\u0e2d\u0e14\u0e44\u0e1f led \u0e0a\u0e38\u0e14\u0e44\u0e1f\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2a\u0e27\u0e34\u0e15\u0e0a\u0e4c \u0e23\u0e35\u0e40\u0e25\u0e22\u0e4c \u0e1f\u0e34\u0e27\u0e2a\u0e4c \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/2  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e 15 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0335569001201\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04\u0e14\u0e35 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001201 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04\u0e14\u0e35 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 affiliate marketing) \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545\\\"\\\" \u60c5\u5831\u901a\u4fe1\u30fbit 16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0335569001228\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001228 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence: ai) \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19\u0e19\u0e34\u0e07 (machine learning) \u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data analytics) \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569002036\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e2d\u0e38\u0e1a\u0e25\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569002036 \u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e2d\u0e38\u0e1a\u0e25 2569-07-31 1000000 71202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 67  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 25 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003476\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003476 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 246  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0353569000521\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e25 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e23\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47214\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47214\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000521 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e25 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e23\u0e14 2569-07-31 1000000 47214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 666  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e25 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0365569001520\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001520 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 420  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0385569000540\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e14\u0e35.\u0e1a\u0e35. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000540 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e14\u0e35.\u0e1a\u0e35. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 181  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003384\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e27\u0e32\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003384 \u0e2b\u0e08.\u0e1a\u0e35\u0e27\u0e32\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-31 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 721\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007331\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e1b \u0e17\u0e39 \u0e2a\u0e27\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007331 \u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e1b \u0e17\u0e39 \u0e2a\u0e27\u0e35\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007349\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007349 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e32\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 395  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007365\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e4c 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007365 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e4c 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e1a\u0e44\u0e21\u0e49 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e21\u0e49\u0e2a\u0e31\u0e1a\u0e22\u0e39\u0e04\u0e32\u0e25\u0e34\u0e1b\u0e15\u0e31\u0e2a \u0e44\u0e21\u0e49\u0e0a\u0e34\u0e1e \u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e44\u0e21\u0e49\u0e17\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e44\u0e21\u0e49\u0e2a\u0e31\u0e1a \u88fd\u9020 233  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007373\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e19\u0e2a\u0e38\u0e27\u0e31\u0e25 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007373 \u0e1a\u0e08.\u0e2a\u0e34\u0e19\u0e2a\u0e38\u0e27\u0e31\u0e25 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 264  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569004072\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e1a\u0e35 \u0e23\u0e39\u0e1f \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004072 \u0e1a\u0e08.\u0e17\u0e35 \u0e1a\u0e35 \u0e23\u0e39\u0e1f \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 41001 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5efa\u8a2d 183  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0453569001128\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0b\u0e21\u0e42\u0e15\u0e22 \u0e0a\u0e39\u0e2a\u0e4c\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001128 \u0e2b\u0e08.\u0e42\u0e0b\u0e21\u0e42\u0e15\u0e22 \u0e0a\u0e39\u0e2a\u0e4c 2569-07-31 1000000 47712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0465569000921\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0d \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000921 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0d \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e32\u0e01\u0e01\u0e32 \u0e14\u0e34\u0e19\u0e2a\u0e2d \u0e22\u0e32\u0e07\u0e25\u0e1a  \u0e44\u0e21\u0e49\u0e1a\u0e23\u0e23\u0e17\u0e31\u0e14 \u0e2a\u0e35 \u0e2a\u0e21\u0e38\u0e14 \u0e41\u0e1f\u0e49\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0493569000431\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e25\u0e39\u0e1e\u0e25\u0e31\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0493569000431 \u0e2b\u0e08.\u0e1a\u0e25\u0e39\u0e1e\u0e25\u0e31\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 2569-07-31 1000000 43210 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u5efa\u8a2d 53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005351\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005351 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e0a\u0e47\u0e2d\u0e1b 2569-07-31 1000000 47630 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016916\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e40\u0e1f\u0e23\u0e0a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016916 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e40\u0e1f\u0e23\u0e0a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 204  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e2a\u0e31\u0e19\u0e1b\u0e48\u0e32\u0e15\u0e2d\u0e07-\u0e41\u0e21\u0e48\u0e27\u0e32\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016924\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e1f\u0e34\u0e25\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016924 \u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e1f\u0e34\u0e25\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016932\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e15\u0e15\u0e23\u0e49\u0e32 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016932 \u0e1a\u0e08.\u0e40\u0e15\u0e15\u0e23\u0e49\u0e32 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e22\u0e48\u0e2d\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23  \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 59\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569002301\",\"name_th\":\"\u0e2b\u0e08.3\u0e14\u0e2d\u0e22\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002301 \u0e2b\u0e08.3\u0e14\u0e2d\u0e22\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 2569-07-31 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 987  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0573569002310\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1f.\u0e40\u0e08.\u0e17\u0e35. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002310 \u0e2b\u0e08.\u0e40\u0e2d\u0e1f.\u0e40\u0e08.\u0e17\u0e35. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-31 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e07\u0e32\u0e19\u0e08\u0e23\u0e32\u0e08\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e49\u0e19\u0e16\u0e19\u0e19 \u0e15\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e25\u0e32\u0e19\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e07\u0e32\u0e19\u0e17\u0e32\u0e2a\u0e35\u0e2d\u0e35\u0e1e\u0e47\u0e2d\u0e01\u0e0b\u0e35\u0e48\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e25\u0e32\u0e14\u0e22\u0e32\u0e07\u0e21\u0e30\u0e15\u0e2d\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e08\u0e23\u0e32\u0e08\u0e23\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e35 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e07\u0e32\u0e19\u0e15\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e08\u0e23\u0e32\u0e08\u0e23 \u5efa\u8a2d 459  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e49\u0e33\u0e25\u0e31\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001801\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e35\u0e2d\u0e35\u0e2d\u0e35\u0e42\u0e2d\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001801 \u0e2b\u0e08.\u0e2d\u0e35\u0e2d\u0e35\u0e2d\u0e35\u0e42\u0e2d 2569-07-31 1000000 47640 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001819\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e32\u0e1a\u0e32\u0e19\u0e48\u0e32\u0e1e\u0e25\u0e31\u0e2a\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001819 \u0e2b\u0e08.\u0e1a\u0e32\u0e1a\u0e32\u0e19\u0e48\u0e32\u0e1e\u0e25\u0e31\u0e2a 2569-07-31 1000000 47640 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001827\",\"name_th\":\"\u0e2b\u0e08.\u0e16\u0e31\u0e07\u0e40\u0e07\u0e34\u0e19 2026\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001827 \u0e2b\u0e08.\u0e16\u0e31\u0e07\u0e40\u0e07\u0e34\u0e19 2026 2569-07-31 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002221\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002221 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e22\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e15\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0623569000766\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04-\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000766 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04-\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c 2569-07-31 1000000 74109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 (process piping) \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 (utility system) \u0e23\u0e30\u0e1a\u0e1a\u0e25\u0e21\u0e2d\u0e31\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33\u0e23\u0e49\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0653569001231\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e04\u0e49\u0e01 \u0e42\u0e0a\u0e04\u0e14\u0e35\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001231 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e04\u0e49\u0e01 \u0e42\u0e0a\u0e04\u0e14\u0e35 2569-07-31 1000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 228  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0735569007699\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e25\u0e40\u0e25\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007699 \u0e1a\u0e08.\u0e04\u0e39\u0e25\u0e40\u0e25\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1b\u0e23\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e41\u0e1b\u0e23\u0e07\u0e14\u0e49\u0e32\u0e21\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e17\u0e33\u0e08\u0e32\u0e01\u0e25\u0e27\u0e14\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e33\u0e08\u0e32\u0e01\u0e02\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 212\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569008091\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 2005 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008091 \u0e1a\u0e08.\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 2005 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86\/119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0765569001534\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e27\u0e31\u0e07\u0e2e\u0e31\u0e48\u0e27 \u0e44\u0e1a\u0e42\u0e2d\u0e41\u0e21\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16210\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16210\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001534 \u0e1a\u0e08.\u0e2b\u0e27\u0e31\u0e07\u0e2e\u0e31\u0e48\u0e27 \u0e44\u0e1a\u0e42\u0e2d\u0e41\u0e21\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 16210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e2d\u0e31\u0e14\u0e41\u0e17\u0e48\u0e07 \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25 \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e2d\u0e31\u0e14\u0e41\u0e17\u0e48\u0e07(wood pellet) \u0e41\u0e25\u0e30\u0e16\u0e48\u0e32\u0e19\u0e08\u0e32\u0e01\u0e01\u0e30\u0e25\u0e32\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u88fd\u9020 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0805569002971\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e17\u0e4c \u0e42\u0e01\u0e23\u0e1f \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e17\u0e34\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002971 \u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e17\u0e4c \u0e42\u0e01\u0e23\u0e1f \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e17\u0e34\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5bbf\u6cca\u30fb\u98f2\u98df 168\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0825569001193\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001193 \u0e1a\u0e08.\u0e2b\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30 \u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e25\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 229\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e254 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569013931\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e15\u0e0a\u0e4c\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013931 \u0e1a\u0e08.\u0e27\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e15\u0e0a\u0e4c\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 17\/6  \u0e16\u0e19\u0e19\u0e42\u0e01\u0e21\u0e32\u0e23\u0e20\u0e31\u0e08\u0e08\u0e4c \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013957\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e40\u0e17\u0e04\u0e1a\u0e34\u0e27\u0e14\u0e34\u0e49\u0e07\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e2a\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e1b\u0e23\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e42\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013957 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e40\u0e17\u0e04\u0e1a\u0e34\u0e27\u0e14\u0e34\u0e49\u0e07\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e2a\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e1b\u0e23\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e42\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 75\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013965\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d \u0e40\u0e2d\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013965 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d \u0e40\u0e2d\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 40\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0843569001469\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e27\u0e35\u0e17\u0e15\u0e35\u0e49\u0e42\u0e2e\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001469 \u0e2b\u0e08.\u0e2a\u0e27\u0e35\u0e17\u0e15\u0e35\u0e49\u0e42\u0e2e\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 2569-07-31 1000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e2d\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e15\u0e32\u0e21\u0e2d\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u88fd\u9020 73\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0843569001477\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e4a\u0e30\u0e1b\u0e4a\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001477 \u0e2b\u0e08.\u0e1b\u0e4a\u0e30\u0e1b\u0e4a\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b 2569-07-31 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 180\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010982\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e0b\u0e36\u0e19\u0e30 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e31\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010982 \u0e1a\u0e08.\u0e04\u0e34\u0e0b\u0e36\u0e19\u0e30 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e31\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 117\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0855569000570\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e01\u0e38\u0e25 \u0e17\u0e39\u0e42\u0e01\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46314\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46314\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000570 \u0e1a\u0e08.\u0e17\u0e39\u0e01\u0e38\u0e25 \u0e17\u0e39\u0e42\u0e01\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46314 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e21\u0e1e\u0e32\u0e2a\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e2a\u0e4c \u0e19\u0e21\u0e2a\u0e14\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07 \u0e19\u0e21\u0e22\u0e39\u0e40\u0e2d\u0e0a\u0e17\u0e35 \u0e19\u0e21\u0e16\u0e31\u0e48\u0e27\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569006453\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e0a\u0e0a\u0e32\u0e20\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006453 \u0e1a\u0e08.\u0e40\u0e27\u0e0a\u0e0a\u0e32\u0e20\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u4e0d\u52d5\u7523 138  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001150\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e27\u0e22\u0e4c\u0e0b \u0e40\u0e25\u0e34\u0e1f \u0e22\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001150 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e27\u0e22\u0e4c\u0e0b \u0e40\u0e25\u0e34\u0e1f \u0e22\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 160\/4  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 5 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0925569001168\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e32\u0e30\u0e21\u0e38\u0e01\u0e14\u0e4c \u0e40\u0e04\u0e2d\u0e40\u0e23\u0e19\u0e0b\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66123\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66123\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001168 \u0e1a\u0e08.\u0e40\u0e01\u0e32\u0e30\u0e21\u0e38\u0e01\u0e14\u0e4c \u0e40\u0e04\u0e2d\u0e40\u0e23\u0e19\u0e0b\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 66123 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u91d1\u878d\u30fb\u4fdd\u967a 65\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0925569001176\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001176 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000000 73200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 23\/34  \u0e16\u0e19\u0e19\u0e27\u0e31\u0e14\u0e19\u0e34\u0e42\u0e04\u0e23\u0e18 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0103569008184\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d \u0e0b\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008184 \u0e2b\u0e08.\u0e40\u0e2d \u0e0b\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-30 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 19 \u0e41\u0e22\u0e01 1-7 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142532\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47511\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47511\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142532 \u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 47511 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e1c\u0e49\u0e32 \u0e1c\u0e37\u0e19\u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d \u0e14\u0e49\u0e32\u0e22 \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 677-681  \u0e16\u0e19\u0e19\u0e08\u0e31\u0e01\u0e23\u0e40\u0e1e\u0e0a\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142541\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e25 \u0e1e\u0e34\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142541 \u0e1a\u0e08.\u0e14\u0e35\u0e25 \u0e1e\u0e34\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 989  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e22\u0e32\u0e21\u0e1e\u0e34\u0e27\u0e23\u0e23\u0e18\u0e19\u0e4c\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12a \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142591\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142591 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 (\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01 (facebook) , \u0e15\u0e34\u0e4a\u0e01\u0e15\u0e47\u0e2d\u0e01 (tiktok) , \u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e35\u0e49 (shopee) , \u0e25\u0e32\u0e0b\u0e32\u0e14\u0e49\u0e32 (lazada) , \u0e44\u0e17\u0e22\u0e21\u0e32\u0e23\u0e4c\u0e17  (thaimart) , \u0e44\u0e25\u0e19\u0e4c \u0e42\u0e2d\u0e40\u0e2d (line oa) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/218  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e19\u0e35\u0e0b \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142613\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e40\u0e1e\u0e47\u0e17 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142613 \u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e40\u0e1e\u0e47\u0e17 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a-\u0e1d\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e15\u0e31\u0e14\u0e02\u0e19\u0e41\u0e25\u0e30\u0e17\u0e33\u0e2a\u0e1b\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 158\/4  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 90 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142630\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e40\u0e21\u0e0b \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142630 \u0e1a\u0e08.\u0e2d\u0e30\u0e40\u0e21\u0e0b \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 39  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2783 (\u0e08\u0e34\u0e15\u0e15\u0e4c\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142656\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e27\u0e4c\u0e41\u0e25\u0e47\u0e1a \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142656 \u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e27\u0e4c\u0e41\u0e25\u0e47\u0e1a \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30 \u0e2b\u0e19\u0e31\u0e07\u0e28\u0e35\u0e23\u0e29\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 74\/1  \u0e0b\u0e2d\u0e22 \u0e21\u0e35\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142664\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d \u0e1e\u0e34\u0e04\u0e40\u0e04\u0e34\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142664 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d \u0e1e\u0e34\u0e04\u0e40\u0e04\u0e34\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 93111 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e01\u0e35\u0e2c\u0e32 \u82b8\u8853\u30fb\u5a2f\u697d 888\/3  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e48\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142711\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1e\u0e31\u0e25\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142711 \u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1e\u0e31\u0e25\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-marketplace) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 364\/83  \u0e2d\u0e32\u0e04\u0e32\u0e23maestro 07 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e16\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142745\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c 83 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142745 \u0e1a\u0e08.\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c 83 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e23\u0e27\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 169\/98  \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e41\u0e22\u0e01 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025137\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e1e \u0e2a\u0e1e\u0e34\u0e23\u0e34\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025137 \u0e1a\u0e08.\u0e0b\u0e34\u0e1e \u0e2a\u0e1e\u0e34\u0e23\u0e34\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 103\/1  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025145\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e18\u0e35\u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025145 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e18\u0e35\u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 4199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 107 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025161\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e42\u0e1b\u0e23 \u0e40\u0e2d\u0e44\u0e2d \u0e40\u0e2d\u0e40\u0e22\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025161 \u0e1a\u0e08.\u0e14\u0e39\u0e42\u0e1b\u0e23 \u0e40\u0e2d\u0e44\u0e2d \u0e40\u0e2d\u0e40\u0e22\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e01\u0e39\u0e49\u0e04\u0e37\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 399\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e1b\u0e39\u0e48\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e21\u0e34\u0e07\u0e1e\u0e23\u0e32\u0e22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025188\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2a\u0e17\u0e34\u0e19\u0e35\u0e48\u0e42\u0e0b\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025188 \u0e1a\u0e08.\u0e40\u0e14\u0e2a\u0e17\u0e34\u0e19\u0e35\u0e48\u0e42\u0e0b\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 (subscription) \u60c5\u5831\u901a\u4fe1\u30fbit 94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569028420\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e38\u0e01\u0e27\u0e35\u0e48\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028420 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e38\u0e01\u0e27\u0e35\u0e48\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e42\u0e09\u0e21 \u0e17\u0e31\u0e49\u0e07 \u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023428\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e19\u0e01\u0e0b\u0e4c \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023428 \u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e19\u0e01\u0e0b\u0e4c \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/171  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e34\u0e42\u0e2d \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35- \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023452\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e2a\u0e01\u0e32\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023452 \u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e2a\u0e01\u0e32\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 64202 \u0e25\u0e07\u0e17\u0e38\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e38\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e14\u0e46 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e43\u0e14\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 79\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023461\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023461 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 10751 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u88fd\u9020 18\/285  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004962\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e23\u0e4c \u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25 \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004962 \u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e23\u0e4c \u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25 \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e40\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0b\u0e2a\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 72\/114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569039480\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e42\u0e04\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039480 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e42\u0e04\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 29\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039510\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e04 \u0e40\u0e04 168 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039510 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e04 \u0e40\u0e04 168 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002403\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002403 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 74200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e27\u0e22\u0e15\u0e19\u0e40\u0e2d\u0e07(self photo studio)\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e39\u0e49\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 ( photobooth) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 30\/22  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e1e\u0e25\u0e34\u0e49\u0e27 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0243569000760\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e25\u0e34\u0e02\u0e34\u0e15 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49209\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49209\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000760 \u0e2b\u0e08.\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e25\u0e34\u0e02\u0e34\u0e15 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-30 1000000 49209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07 \u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u904b\u8f38\u30fb\u7269\u6d41 40\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569007765\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e28\u0e34\u0e23\u0e34 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007765 \u0e1a\u0e08.\u0e1e\u0e25\u0e28\u0e34\u0e23\u0e34 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 589\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007773\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e27\u0e34\u0e17 \u0e1e\u0e23\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007773 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e27\u0e34\u0e17 \u0e1e\u0e23\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e32\u0e07\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e35\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 2211\/2  \u0e16\u0e19\u0e19\u0e21\u0e38\u0e02\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0415569004064\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e1a\u0e32\u0e40\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004064 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e1a\u0e32\u0e40\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e43\u0e19\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e44\u0e2d\u0e40\u0e17\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 301  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0473569001021\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e01\u0e27\u0e34\u0e19  \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569001021 \u0e2b\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e01\u0e27\u0e34\u0e19  \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c 2569-07-30 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004896\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e21 \u0e19\u0e34\u0e18 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004896 \u0e1a\u0e08.\u0e40\u0e2b\u0e21 \u0e19\u0e34\u0e18 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 82301 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 300\/111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0655569002442\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e40\u0e17\u0e40\u0e25\u0e2a\u0e17\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002442 \u0e1a\u0e08.\u0e40\u0e17\u0e40\u0e17\u0e40\u0e25\u0e2a\u0e17\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 266\/120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002451\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e1e\u0e49\u0e2d\u0e22\u0e17\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33122\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33122\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002451 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e1e\u0e49\u0e2d\u0e22\u0e17\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 33122 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19  \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 222\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0703569000510\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e27\u0e32\u0e23\u0e35 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0703569000510 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e27\u0e32\u0e23\u0e35 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-30 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001150\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e49\u0e32\u0e21\u0e32\u0e25\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001150 \u0e2b\u0e08.\u0e1b\u0e49\u0e32\u0e21\u0e32\u0e25\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-30 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e49\u0e32\u0e27\u0e41\u0e01\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 421  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007672\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2d\u0e25\u0e25\u0e35\u0e48 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007672 \u0e1a\u0e08.\u0e1e\u0e2d\u0e25\u0e25\u0e35\u0e48 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 5\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007681\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e39\u0e49\u0e14 \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\u0e41\u0e21\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56292\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56292\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007681 \u0e1a\u0e08.\u0e1f\u0e39\u0e49\u0e14 \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\u0e41\u0e21\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 56292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e25\u0e32\u0e07\u0e27\u0e31\u0e19\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e19\u0e32 \u5bbf\u6cca\u30fb\u98f2\u98df 8\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569008059\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a.\u0e42\u0e1e\u0e23\u0e40\u0e1e\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008059 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a.\u0e42\u0e1e\u0e23\u0e40\u0e1e\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 25999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e1a\u0e1e\u0e31\u0e14\u0e40\u0e23\u0e37\u0e2d\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e25\u0e2b\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 8\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013892\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013892 \u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22) \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 39\/1  \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010966\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e35\u0e19 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010966 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e35\u0e19 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569006372\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e23\u0e34 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006372 \u0e1a\u0e08.\u0e20\u0e39\u0e23\u0e34 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 137\/90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0955569000625\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000625 \u0e1a\u0e08.\u0e0a\u0e31\u0e22 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e23\u0e30\u0e1a\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e25\u0e07\u0e43\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e32 \u0e0a\u0e38\u0e14\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 (\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e04\u0e33 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e40\u0e1b\u0e23\u0e14\u0e0a\u0e35\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2f\u0e25\u0e2f) \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e31\u0e48\u0e27\u0e46 \u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e14\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e08\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e23\u0e30\u0e1a\u0e1a gis \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e14\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e21\u0e32\u0e01\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1a\u0e35\u0e1a\u0e2d\u0e31\u0e14\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e27\u0e23\u0e31\u0e2a \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e31\u0e01\u0e29\u0e23 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e48\u0e32\u0e19\u0e44\u0e1f\u0e25\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e08\u0e14\u0e08\u0e33\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2b\u0e23\u0e37\u0e2d \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e42\u0e14\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e01\u0e1e\u0e32 \u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 (pda) \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e25\u0e07\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e19 windows live \u60c5\u5831\u901a\u4fe1\u30fbit 21\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569008168\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008168 \u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e0a\u0e31\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2569-07-29 1000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 75 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142338\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e27\u0e32\u0e22 \u0e41\u0e04\u0e23\u0e4c \u0e41\u0e2d\u0e21\u0e1a\u0e39\u0e41\u0e25\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142338 \u0e1a\u0e08.\u0e1a\u0e35\u0e27\u0e32\u0e22 \u0e41\u0e04\u0e23\u0e4c \u0e41\u0e2d\u0e21\u0e1a\u0e39\u0e41\u0e25\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 748  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142354\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e19\u0e32\u0e04 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45402\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45402\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142354 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e19\u0e32\u0e04 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 45402 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 301\/442  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0768(\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142362\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e23\u0e32\u0e40\u0e17\u0e04 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142362 \u0e1a\u0e08.\u0e22\u0e39\u0e23\u0e32\u0e40\u0e17\u0e04 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e44\u0e23\u0e49\u0e04\u0e19\u0e02\u0e31\u0e1a (uav) \u0e42\u0e14\u0e23\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e17\u0e2b\u0e32\u0e23 \u0e42\u0e14\u0e23\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e42\u0e14\u0e23\u0e19\u0e2a\u0e2d\u0e14\u0e41\u0e19\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e48\u0e2d\u0e15\u0e49\u0e32\u0e19\u0e42\u0e14\u0e23\u0e19 (anti-drone) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1899\/131  \u0e16\u0e19\u0e19\u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142371\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e2d\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142371 \u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e2d\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e32 \u0e04\u0e23\u0e35\u0e21\u0e25\u0e14\u0e23\u0e2d\u0e22\u0e41\u0e1c\u0e25\u0e40\u0e1b\u0e47\u0e19 \u0e04\u0e23\u0e35\u0e21\u0e25\u0e14\u0e23\u0e2d\u0e22\u0e2a\u0e34\u0e27 \u0e04\u0e23\u0e35\u0e21\u0e25\u0e14\u0e1d\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e38\u0e14\u0e14\u0e48\u0e32\u0e07\u0e14\u0e33 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2794 (\u0e1b\u0e31\u0e0d\u0e08\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142397\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e35\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142397 \u0e1a\u0e08.\u0e18\u0e35\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e43\u0e19\u0e23\u0e48\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u6559\u80b2 2  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142401\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e22\u0e4c\u0e1a\u0e23\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142401 \u0e1a\u0e08.\u0e40\u0e1a\u0e22\u0e4c\u0e1a\u0e23\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/996  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 41 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142419\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e40\u0e15\u0e4b\u0e2d2563 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142419 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e40\u0e15\u0e4b\u0e2d2563 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/6-7  \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142427\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e17\u0e23\u0e34\u0e04 \u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e23\u0e4c \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142427 \u0e1a\u0e08.\u0e41\u0e1e\u0e17\u0e23\u0e34\u0e04 \u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e23\u0e4c \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e23\u0e49\u0e32\u0e19\u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04  \u0e04\u0e35\u0e2d\u0e2d\u0e2a\u0e01\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 24\/19  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142443\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e23\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142443 \u0e1a\u0e08.\u0e41\u0e04\u0e23\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e19\u0e31\u0e48\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e1a\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a (take away) \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 478,480  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142460\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e35\u0e48\u0e1e\u0e23\u0e30\u0e1e\u0e31\u0e01\u0e15\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142460 \u0e1a\u0e08.\u0e2a\u0e35\u0e48\u0e1e\u0e23\u0e30\u0e1e\u0e31\u0e01\u0e15\u0e23\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 425\/1  \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142478\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e25\u0e21\u0e48\u0e2d\u0e19\u0e2d\u0e49\u0e27\u0e19\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142478 \u0e1a\u0e08.\u0e41\u0e0b\u0e25\u0e21\u0e48\u0e2d\u0e19\u0e2d\u0e49\u0e27\u0e19\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 56\/68  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 56 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142494\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e04\u0e39\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142494 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e04\u0e39\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23  \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 287\/14  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32 78 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e25\u0e33\u0e01\u0e2d\u0e44\u0e1c\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142508\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e47\u0e04\u0e40\u0e17\u0e40\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142508 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e47\u0e04\u0e40\u0e17\u0e40\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e2a\u0e30\u0e2a\u0e21 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21 (trading card game : tcg) \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e1f\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1021\/2  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 46 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025072\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e14\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025072 \u0e1a\u0e08.\u0e18\u0e19\u0e14\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 223\/71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025081\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025081 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e22\u0e37\u0e48\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e02\u0e2d\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e15\u0e32\u0e21\u0e23\u0e30\u0e1a\u0e1a mou \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 122\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025099\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32\u0e41\u0e25\u0e47\u0e1a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025099 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32\u0e41\u0e25\u0e47\u0e1a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 (networking) \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 898\/215  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e1f \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 90 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 90 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025102\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e0a \u0e21\u0e32\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025102 \u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e0a \u0e21\u0e32\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 387\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e43\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025129\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e41\u0e27\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"61101\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"61101\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025129 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e41\u0e27\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 61101 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e35\u0e48\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 89\/245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569028373\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c \u0e1a\u0e34\u0e27\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028373 \u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c \u0e1a\u0e34\u0e27\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 92\/68  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028381\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028381 \u0e1a\u0e08.\u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u5efa\u8a2d 217 219  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4037 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023380\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e40\u0e14\u0e0b\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023380 \u0e1a\u0e08.\u0e42\u0e04\u0e40\u0e14\u0e0b\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 (license) \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33         \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32         \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 \u60c5\u5831\u901a\u4fe1\u30fbit 35\/115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e21 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023398\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023398 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 49\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023401\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e41\u0e25\u0e47\u0e1a \u0e41\u0e1f\u0e04\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023401 \u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e41\u0e25\u0e47\u0e1a \u0e41\u0e1f\u0e04\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023410\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023410 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 165\/143  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0173569000175\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e31\u0e28\u0e19\u0e34\u0e08\u0e14\u0e32\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0173569000175 \u0e2b\u0e08.\u0e17\u0e31\u0e28\u0e19\u0e34\u0e08\u0e14\u0e32 2569-07-29 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003327\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e41\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95220\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95220\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003327 \u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e41\u0e2d\u0e23\u0e4c 2569-07-29 1000000 95220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e25\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 79\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569010040\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e0d\u0e27\u0e31\u0e25\u0e22\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010040 \u0e1a\u0e08.\u0e0a\u0e32\u0e0d\u0e27\u0e31\u0e25\u0e22\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 1\/2  \u0e16\u0e19\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1c\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0305569007757\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007757 \u0e1a\u0e08.\u0e0b\u0e35\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 66191 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e2a\u0e2d\u0e19 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 11\/6  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e11 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0403569003376\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e32\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003376 \u0e2b\u0e08.\u0e19\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e32 2569-07-29 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2a\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e25\u0e47\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 194\/172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c 39 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007322\",\"name_th\":\"\u0e1a\u0e08. \u0e17\u0e33\u0e14\u0e35 \u0e0a\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10769\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10769\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007322 \u0e1a\u0e08. \u0e17\u0e33\u0e14\u0e35 \u0e0a\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 10769 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e22\u0e32 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 171  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001748\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e21\u0e48\u0e41\u0e1e\u0e19\u0e40\u0e04\u0e49\u0e01 8888\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001748 \u0e2b\u0e08.\u0e41\u0e21\u0e48\u0e41\u0e1e\u0e19\u0e40\u0e04\u0e49\u0e01 8888 2569-07-29 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0445569001812\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e27\u0e22\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001812 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e27\u0e22\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/1  \u0e0b\u0e2d\u0e22 \u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c 66 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0505569016843\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e2d\u0e34\u0e07\u0e04\u0e4c \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016843 \u0e1a\u0e08.\u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e2d\u0e34\u0e07\u0e04\u0e4c \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 26\/1  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22 5 (\u0e16\u0e19\u0e19\u0e19\u0e34\u0e21\u0e21\u0e32\u0e19\u0e40\u0e2b\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c) \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0735569007664\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e2b\u0e25\u0e27\u0e07 \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007664 \u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e2b\u0e25\u0e27\u0e07 \u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 135\/307-309  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569008032\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e08\u0e23\u0e34\u0e0d 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008032 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e08\u0e23\u0e34\u0e0d 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/432  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569008041\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e19\u0e31\u0e0a\u0e0a\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008041 \u0e1a\u0e08.\u0e18\u0e19\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e19\u0e31\u0e0a\u0e0a\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0805569002963\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e48\u0e2d\u0e21\u0e35\u0e48 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e1f\u0e23\u0e19\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002963 \u0e1a\u0e08.\u0e40\u0e25\u0e48\u0e2d\u0e21\u0e35\u0e48 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e1f\u0e23\u0e19\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 85499 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e15\u0e33\u0e23\u0e32 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1d\u0e36\u0e01\u0e2b\u0e31\u0e14 \u0e41\u0e25\u0e30 \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u6559\u80b2 28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e25\u0e34\u0e49\u0e21\u0e01\u0e32\u0e40\u0e09\u0e37\u0e49\u0e2d\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0905569006356\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006356 \u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 37\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001141\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e32\u0e22 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001141 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e32\u0e22 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 167  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0105569142214\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142214 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u6559\u80b2 32\/78  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e1c\u0e48\u0e17\u0e2d\u0e07 2 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142222\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1b\u0e31\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142222 \u0e1a\u0e08.\u0e14\u0e35\u0e1b\u0e31\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/44  \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142231\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e34\u0e27\u0e32 \u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142231 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e34\u0e27\u0e32 \u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 14120 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u88fd\u9020 142\/72  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e42\u0e0b\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 142\/72 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27102 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142249\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142249 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e02\u0e2d\u0e07\u0e40\u0e40\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27  \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 220  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142257\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e25 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142257 \u0e1a\u0e08.\u0e0b\u0e35\u0e25 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1f\u0e31\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01 \u533b\u7642\u30fb\u798f\u7949 111\/488-489  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 19 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142265\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e04\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e0b\u0e2d\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142265 \u0e1a\u0e08.\u0e0b\u0e35\u0e04\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e0b\u0e2d\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 48\/631  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 41 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142273\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e2a\u0e18\u0e35\u0e17\u0e34\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142273 \u0e1a\u0e08.\u0e1a\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e2a\u0e18\u0e35\u0e17\u0e34\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 70209 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 (agency) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 69\/288  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 48 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142281\",\"name_th\":\"\u0e1a\u0e08. \u0e42\u0e2d\u0e25\u0e48\u0e32\u0e42\u0e2d\u0e25\u0e48\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142281 \u0e1a\u0e08. \u0e42\u0e2d\u0e25\u0e48\u0e32\u0e42\u0e2d\u0e25\u0e48\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e25\u0e21\u0e48\u0e32 \u0e19\u0e27\u0e14\u0e1b\u0e23\u0e30\u0e04\u0e1a\u0e2b\u0e34\u0e19\u0e23\u0e49\u0e2d\u0e19 \u0e19\u0e27\u0e14\u0e2e\u0e2d\u0e14\u0e2d\u0e2d\u0e22 \u0e19\u0e27\u0e14\u0e40\u0e17\u0e49\u0e32\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 2\/19  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 22 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142290\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142290 \u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/315  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0f\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142311\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e42\u0e21\u0e15\u0e34\u0e42\u0e2d  \u0e1e\u0e23\u0e35\u0e21\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28221\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28221\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142311 \u0e1a\u0e08.\u0e40\u0e23\u0e42\u0e21\u0e15\u0e34\u0e42\u0e2d  \u0e1e\u0e23\u0e35\u0e21\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 28221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e02\u0e22\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e02\u0e22\u0e30 \u88fd\u9020 159  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 76 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025021\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025021 \u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e23\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 57\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025030\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a.\u0e1a\u0e35.\u0e0b\u0e35. \u0e40\u0e14\u0e42\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025030 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a.\u0e1a\u0e35.\u0e0b\u0e35. \u0e40\u0e14\u0e42\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e15\u0e39\u0e49\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e25\u0e32\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e15\u0e39\u0e49\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e25\u0e32\u0e19\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e15\u0e39\u0e49\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e15\u0e39\u0e49\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e15\u0e39\u0e49\u0e40\u0e1b\u0e25\u0e48\u0e32\u0e41\u0e25\u0e30\u0e15\u0e39\u0e49\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 9\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025048\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e19\u0e42\u0e14\u0e21\u0e32\u0e23\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025048 \u0e1a\u0e08.\u0e0a\u0e34\u0e19\u0e42\u0e14\u0e21\u0e32\u0e23\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (e-commerce) \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e35\u0e49 \u0e25\u0e32\u0e0b\u0e32\u0e14\u0e49\u0e32 \u0e40\u0e1f\u0e2a\u0e1a\u0e38\u0e4a\u0e04 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e4a\u0e01\u0e15\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/54  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 40 \u0e14\u0e35\u0e44\u0e25\u0e17\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002330\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e27\u0e25\u0e32\u0e17\u0e32\u0e40\u0e25\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58192\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58192\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002330 \u0e2b\u0e08.\u0e40\u0e27\u0e25\u0e32\u0e17\u0e32\u0e40\u0e25\u0e19\u0e17\u0e4c 2569-07-28 1000000 58192 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e14 \u0e07\u0e32\u0e19\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 105\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0123569002348\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e27\u0e34\u0e21\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002348 \u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e27\u0e34\u0e21\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-28 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 8\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028292\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e40\u0e15\u0e47\u0e21\u0e04\u0e25\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96304\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96304\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028292 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e40\u0e15\u0e47\u0e21\u0e04\u0e25\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 96304 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 116\/147  \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028306\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e48\u0e07\u0e40\u0e1b\u0e32 \u0e21\u0e2b\u0e32\u0e40\u0e2e\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028306 \u0e1a\u0e08.\u0e2d\u0e31\u0e48\u0e07\u0e40\u0e1b\u0e32 \u0e21\u0e2b\u0e32\u0e40\u0e2e\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e32\u0e27 \u0e2b\u0e27\u0e32\u0e19 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 89\/151  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c (\u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48-\u0e1a\u0e32\u0e07\u0e04\u0e39\u0e25\u0e31\u0e14 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028322\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e2a\u0e17\u0e04\u0e34\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"15121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"15121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028322 \u0e1a\u0e08.\u0e25\u0e2d\u0e2a\u0e17\u0e04\u0e34\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 15121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u88fd\u9020 134\/363  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e31\u0e2a\u0e0b\u0e34\u0e15\u0e35\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\u0e19\u0e49\u0e33 \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028331\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028331 \u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e1a\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e0a\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e0d\u52d5\u7523 119\/1010  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028349\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028349 \u0e1a\u0e08.\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e42\u0e23\u0e07\u0e22\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 38\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028357\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e1a\u0e35\u0e40\u0e2d\u0e0a \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028357 \u0e1a\u0e08.\u0e08\u0e35\u0e1a\u0e35\u0e40\u0e2d\u0e0a \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 9 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028365\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46491\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46491\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028365 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 46491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023363\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e04 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023363 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e04 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e29\u0e35 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 365\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0155569000631\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e0a\u0e35\u0e17 \u0e2d\u0e47\u0e2d\u0e1a\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000631 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e0a\u0e35\u0e17 \u0e2d\u0e47\u0e2d\u0e1a\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e39\u0e18\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e40\u0e27\u0e17\u0e35 \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 16\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0203569003319\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003319 \u0e2b\u0e08.\u0e40\u0e04\u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-28 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 24\/12  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e38\u0e02\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e0b\u0e2d\u0e22 12 \u0e16\u0e19\u0e19\u0e25\u0e07\u0e2b\u0e32\u0e14\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039412\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039412 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 126\/256  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569010023\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010023 \u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/77  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e09\u0e31\u0e15\u0e23\u0e1e\u0e07\u0e28\u0e4c 3 \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e41\u0e2b\u0e25\u0e21\u0e1e\u0e22\u0e2d\u0e21 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0223569000361\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e4c \u0e1a\u0e34\u0e25\u0e17\u0e4c\u0e2d\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000361 \u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e4c \u0e1a\u0e34\u0e25\u0e17\u0e4c\u0e2d\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-28 1000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e27\u0e17\u0e4c\u0e2d\u0e34\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e25\u0e2d\u0e22\u0e15\u0e31\u0e27\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 9\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0235569000451\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e14\u0e21\u0e32\u0e15\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85101\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85101\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0235569000451 \u0e1a\u0e08.\u0e19\u0e31\u0e14\u0e21\u0e32\u0e15\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 85101 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e27\u0e14\u0e27\u0e34\u0e0a\u0e32 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e:             \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d            \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e15\u0e33\u0e23\u0e32 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07             \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01            \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u6559\u80b2 6\/8  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0305569007731\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01 \u0e42\u0e01 \u0e42\u0e27\u0e25\u0e15\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007731 \u0e1a\u0e08.\u0e42\u0e01 \u0e42\u0e01 \u0e42\u0e27\u0e25\u0e15\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 1870\/1  \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0343569002028\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e34\u0e23\u0e15\u0e34\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569002028 \u0e2b\u0e08.\u0e01\u0e34\u0e23\u0e15\u0e34\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-28 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e14\u0e34\u0e19 \u0e25\u0e39\u0e01\u0e23\u0e31\u0e07 \u0e2b\u0e34\u0e19\u0e04\u0e25\u0e38\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 198\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0365569001511\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001511 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0403569003368\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003368 \u0e2b\u0e08.\u0e15\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c 2569-07-28 1000000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e29\u0e32 \u0e40\u0e40\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e20\u0e32\u0e29\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u6559\u80b2 199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007314\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e34\u0e19 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007314 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e34\u0e19 \u0e42\u0e2e\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 555\/251  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569004030\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e1a\u0e4c\u0e14\u0e34\u0e08\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004030 \u0e1a\u0e08.\u0e44\u0e27\u0e1a\u0e4c\u0e14\u0e34\u0e08\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30  (smart devices) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 346\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569004056\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2025 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004056 \u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2025 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 272  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016827\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e47\u0e1b\u0e40\u0e1e\u0e19 \u0e42\u0e04\u0e48\u0e22 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016827 \u0e1a\u0e08.\u0e40\u0e17\u0e47\u0e1b\u0e40\u0e1e\u0e19 \u0e42\u0e04\u0e48\u0e22 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e04\u0e32\u0e23\u0e4c\u0e1b\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 292  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001498\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74909\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74909\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001498 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 74909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c (inspection), \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (sorting), \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e0b\u0e49\u0e33 (re-screen) \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e (containment) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 44\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0515569001510\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10761\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10761\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001510 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 10761 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e31\u0e48\u0e27 \u0e1a\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e01\u0e32\u0e41\u0e1f \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e07\u0e01\u0e32\u0e41\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 178\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001803\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1e\u0e23\u0e2b\u0e21\u0e1b\u0e31\u0e0d\u0e42\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001803 \u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1e\u0e23\u0e2b\u0e21\u0e1b\u0e31\u0e0d\u0e42\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e34\u0e25\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e40\u0e01\u0e32\u0e30\u0e04\u0e32-\u0e19\u0e32\u0e42\u0e1b\u0e48\u0e07\u0e2b\u0e32\u0e0d \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004888\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e06\u0e32 \u0e44\u0e2e\u0e2d\u0e30\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004888 \u0e1a\u0e08.\u0e40\u0e21\u0e06\u0e32 \u0e44\u0e2e\u0e2d\u0e30\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 352  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e2a\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0663569000626\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47911\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47911\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0663569000626 \u0e2b\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2569-07-28 1000000 47911 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0725569002247\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002247 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 71202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e25\u0e30\u0e0a\u0e35\u0e49\u0e0a\u0e48\u0e2d\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569003171\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e35 \u0e14\u0e39\u0e1a\u0e31\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003171 \u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e35 \u0e14\u0e39\u0e1a\u0e31\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 35102 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569013841\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17\u0e2a\u0e4c \u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013841 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17\u0e2a\u0e4c \u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 47734 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/1  \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e1e\u0e48\u0e2d\u0e27\u0e31\u0e14\u0e09\u0e25\u0e2d\u0e07 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013850\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013850 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 54\/172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013876\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 (888) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013876 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 (888) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 10\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0903569001832\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e43\u0e08\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001832 \u0e2b\u0e08.\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e43\u0e08 2569-07-28 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 13\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569008125\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e2d\u0e2a.\u0e17\u0e35.\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008125 \u0e2b\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e2d\u0e2a.\u0e17\u0e35.\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-27 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/83  \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569008133\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e39\u0e25 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25 \u0e1a\u0e23\u0e32\u0e27\u0e19\u0e35\u0e48\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008133 \u0e2b\u0e08.\u0e04\u0e39\u0e25 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25 \u0e1a\u0e23\u0e32\u0e27\u0e19\u0e35\u0e48 2569-07-27 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e1a\u0e23\u0e32\u0e27\u0e19\u0e35\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179\/33  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e0a\u0e31\u0e01\u0e1e\u0e23\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569008141\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e1f\u0e23\u0e0a-\u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008141 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e1f\u0e23\u0e0a-\u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-27 1000000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e39\u0e21\u0e49\u0e32\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179\/33  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e0a\u0e31\u0e01\u0e1e\u0e23\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141358\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e2d\u0e40\u0e19\u0e2a\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141358 \u0e1a\u0e08.\u0e2e\u0e2d\u0e40\u0e19\u0e2a\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 14  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1954\/1 \u0e41\u0e22\u0e018-4-3 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141366\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e14\u0e35\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141366 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e14\u0e35\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1104\/311  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25 \u0e04\u0e34\u0e27\u0e1a\u0e4c \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141374\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e31\u0e2a-\u0e27\u0e31\u0e19 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141374 \u0e1a\u0e08.\u0e1e\u0e25\u0e31\u0e2a-\u0e27\u0e31\u0e19 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/33  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141391\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e48\u0e2d\u0e07\u0e01\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e4c\u0e21\u0e31\u0e19\u0e2a\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141391 \u0e1a\u0e08.\u0e2e\u0e48\u0e2d\u0e07\u0e01\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e4c\u0e21\u0e31\u0e19\u0e2a\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 131\/233  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141404\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e15\u0e27\u0e31\u0e19\u0e42\u0e15\u0e04\u0e37\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"60203\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"60203\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141404 \u0e1a\u0e08.\u0e42\u0e15\u0e27\u0e31\u0e19\u0e42\u0e15\u0e04\u0e37\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 60203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u60c5\u5831\u901a\u4fe1\u30fbit 95\/654  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141412\",\"name_th\":\"\u0e1a\u0e08. \u0e19\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e20\u0e32\u0e27\u0e19\u0e32\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141412 \u0e1a\u0e08. \u0e19\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e20\u0e32\u0e27\u0e19\u0e32\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e49\u0e32\u0e44\u0e15\u0e23\u0e08\u0e35\u0e27\u0e23 \u0e08\u0e35\u0e27\u0e23 \u0e2a\u0e1a\u0e07 \u0e2a\u0e31\u0e07\u0e06\u0e32\u0e0f\u0e34 \u0e2d\u0e31\u0e07\u0e2a\u0e30 \u0e1c\u0e49\u0e32\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e1d\u0e19 \u0e23\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e04\u0e15 \u0e22\u0e48\u0e32\u0e21\u0e1e\u0e23\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e27\u0e0a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e06\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1a\u0e32\u0e15\u0e23 \u0e02\u0e32\u0e1a\u0e32\u0e15\u0e23 \u0e16\u0e25\u0e01\u0e1a\u0e32\u0e15\u0e23 \u0e15\u0e32\u0e25\u0e1b\u0e31\u0e15\u0e23 \u0e2d\u0e32\u0e2a\u0e19\u0e30 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19 \u0e2b\u0e21\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e23\u0e30\u0e20\u0e34\u0e01\u0e29\u0e38 \u0e2a\u0e32\u0e21\u0e40\u0e13\u0e23 \u0e41\u0e21\u0e48\u0e0a\u0e35 \u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 76 \u0e41\u0e22\u0e01 1-3-1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141421\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e0a\u0e0a\u0e31\u0e21\u0e2a\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141421 \u0e1a\u0e08.\u0e2d\u0e31\u0e0a\u0e0a\u0e31\u0e21\u0e2a\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 43210 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a solar rooftop \u5efa\u8a2d 17\/26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e27\u0e32\u0e23\u0e3559 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e27\u0e32\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141439\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e40\u0e21\u0e19\u0e17\u0e34\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141439 \u0e1a\u0e08.\u0e25\u0e39\u0e40\u0e21\u0e19\u0e17\u0e34\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 1035\/20  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141447\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e41\u0e2d\u0e25 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141447 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e41\u0e2d\u0e25 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 18\/53  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 25 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141471\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141471 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3079\/9  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141480\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e40\u0e14\u0e19\u0e17\u0e2d\u0e25 \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32502\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32502\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141480 \u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e40\u0e14\u0e19\u0e17\u0e2d\u0e25 \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 32502 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e47\u0e1a\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21  \u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u88fd\u9020 98\/100  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 94 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141501\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141501 \u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e41\u0e25\u0e47\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u533b\u7642\u30fb\u798f\u7949 48  \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e19\u0e32\u0e19\u0e34\u0e04\u0e21 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141510\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e32\u0e19\u0e42\u0e15\u0e4a\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47594\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47594\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141510 \u0e1a\u0e08.\u0e2b\u0e25\u0e32\u0e19\u0e42\u0e15\u0e4a\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47594 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e22\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e25\u0e33\u0e42\u0e1e\u0e07 \u0e44\u0e21\u0e42\u0e04\u0e23\u0e42\u0e1f\u0e19 \u0e2a\u0e32\u0e22\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 135  \u0e0b\u0e2d\u0e22 \u0e44\u0e0a\u0e42\u0e22 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141536\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e17\u0e39\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141536 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e17\u0e39\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e1c\u0e48\u0e17\u0e2d\u0e07 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 3 \u0e0b\u0e2d\u0e22 5 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141552\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e21\u0e1f\u0e25\u0e2d\u0e23\u0e48\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32904\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32904\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141552 \u0e1a\u0e08.\u0e42\u0e1f\u0e21\u0e1f\u0e25\u0e2d\u0e23\u0e48\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 32904 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e41\u0e2b\u0e49\u0e07 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 49\/5,49\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141609\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46317\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46317\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141609 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e2d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46317 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e0a\u0e47\u0e2d\u0e01\u0e42\u0e01\u0e41\u0e25\u0e15 \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e42\u0e01\u0e42\u0e01\u0e49 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e42\u0e01\u0e42\u0e01\u0e49 \u0e01\u0e32\u0e41\u0e1f  \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e01\u0e32\u0e41\u0e1f \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e25\u0e39\u0e01\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/178  \u0e16\u0e19\u0e19\u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141617\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e17\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141617 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e17\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e1a\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u82b8\u8853\u30fb\u5a2f\u697d 135\/8   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1e \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e49\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141633\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e34\u0e01\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141633 \u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e34\u0e01\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e22\u0e32\u0e41\u0e25\u0e30\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c  \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 215\/38  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141641\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e19\u0e14\u0e35 \u0e41\u0e2d\u0e25\u0e1e\u0e35\u0e27\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141641 \u0e1a\u0e08.\u0e1b\u0e31\u0e19\u0e14\u0e35 \u0e41\u0e2d\u0e25\u0e1e\u0e35\u0e27\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e40\u0e02\u0e19\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 14\/30  \u0e2d\u0e32\u0e04\u0e32\u0e23c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 14\/30 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1f\u0e25\u0e2d\u0e23\u0e48\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 51 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141668\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e14\u0e35\u0e25 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141668 \u0e1a\u0e08.\u0e44\u0e2d\u0e14\u0e35\u0e25 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/20  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 5 \u0e41\u0e22\u0e01 18 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141676\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e19\u0e2a\u0e27\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141676 \u0e1a\u0e08.\u0e04\u0e19\u0e2a\u0e27\u0e22\u0e08\u0e33\u0e19\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u82b8\u8853\u30fb\u5a2f\u697d 592\/89  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141684\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e34\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85422\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85422\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141684 \u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e34\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 85422 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e34\u0e01\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e17\u0e24\u0e29\u0e0e\u0e35 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u6559\u80b2 8  \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d 25  \u0e41\u0e22\u0e01 4 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141714\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e2d\u0e0a\u0e21\u0e35\u0e19\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81299\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81299\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141714 \u0e1a\u0e08.\u0e27\u0e2d\u0e0a\u0e21\u0e35\u0e19\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 81299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e02\u0e31\u0e14\u0e2a\u0e35 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e02\u0e31\u0e14\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e1a\u0e32\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 10  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141722\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e42\u0e22\u0e23\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141722 \u0e1a\u0e08.\u0e44\u0e17\u0e42\u0e22\u0e23\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47912 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 322\/8  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141749\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e25\u0e21\u0e32\u0e28 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141749 \u0e1a\u0e08.\u0e0a\u0e25\u0e21\u0e32\u0e28 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 234\/198  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1a\u0e23\u0e34\u0e17\u0e32\u0e40\u0e19\u0e35\u0e22 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141757\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32\u0e41\u0e1a\u0e23\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141757 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32\u0e41\u0e1a\u0e23\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e21\u0e32\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e21\u0e32\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 8\/23  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e17\u0e23\u0e19\u0e14\u0e35\u0e49\u0e18\u0e32\u0e23\u0e32 \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141765\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e21\u0e39\u0e49\u0e14 \u0e01\u0e39\u0e4a\u0e14\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141765 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e21\u0e39\u0e49\u0e14 \u0e01\u0e39\u0e4a\u0e14\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21  \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222\/326  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141773\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e21\u0e32\u0e23\u0e34\u0e42\u0e01\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141773 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e21\u0e32\u0e23\u0e34\u0e42\u0e01\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 167\/6  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141781\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e38\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141781 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e38\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 167\/6  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141790\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141790 \u0e1a\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 167\/6  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141803\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e44\u0e17\u0e22\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141803 \u0e1a\u0e08.\u0e40\u0e25\u0e44\u0e17\u0e22\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 167\/6  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141811\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e27\u0e40\u0e25\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141811 \u0e1a\u0e08.\u0e0a\u0e32\u0e27\u0e40\u0e25\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e4830 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141820\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141820 \u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e07 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e4830 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141838\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141838 \u0e1a\u0e08.\u0e1e\u0e35\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e42\u0e23\u0e04 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e09\u0e35\u0e14\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e15\u0e31\u0e14\u0e02\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e17\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 (lab) \u0e01\u0e32\u0e23\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e0b\u0e32\u0e27\u0e19\u0e14\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 668\/61  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141846\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e1f\u0e34\u0e0a\u0e40\u0e1a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141846 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e1f\u0e34\u0e0a\u0e40\u0e1a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21110 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141854\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e40\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141854 \u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e40\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21110 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141862\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e0b\u0e35 \u0e1e\u0e39\u0e25 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141862 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e0b\u0e35 \u0e1e\u0e39\u0e25 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 43909 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u5efa\u8a2d 2\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e19\u0e40\u0e17\u0e35\u0e22\u0e23\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141889\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1b\u0e34\u0e4a\u0e1b\u0e1b\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141889 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1b\u0e34\u0e4a\u0e1b\u0e1b\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/96  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 7 \u0e41\u0e22\u0e01 6 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 - \u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141901\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e14\u0e4c\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141901 \u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e14\u0e4c\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e2a\u0e4c) \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 45\/100  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e2a\u0e38\u0e02\u0e43\u0e08 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141951\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e15\u0e31\u0e21 \u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141951 \u0e1a\u0e08.\u0e40\u0e14\u0e15\u0e31\u0e21 \u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e01\u0e39\u0e49\u0e04\u0e37\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e08\u0e32\u0e01\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e17\u0e35\u0e48\u0e08\u0e30\u0e21\u0e35\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28) \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 5   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 101 \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e40\u0e01\u0e49\u0e32 54(\u0e0b\u0e2d\u0e22 5 \u0e40\u0e2a\u0e23\u0e35 7) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141978\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141978 \u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e40\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19) \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 181\/224  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c 32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141986\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e25 \u0e40\u0e0c\u0e2d\u0e23\u0e35\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141986 \u0e1a\u0e08.\u0e40\u0e01\u0e25 \u0e40\u0e0c\u0e2d\u0e23\u0e35\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e20\u0e32\u0e04\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 (ground transportation services) \u904b\u8f38\u30fb\u7269\u6d41 1\/88  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e0a\u0e32\u0e14 10 \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e41\u0e01\u0e07\u0e32\u0e21 14 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141994\",\"name_th\":\"\u0e1a\u0e08.\u0e1c\u0e25\u0e40\u0e25\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141994 \u0e1a\u0e08.\u0e1c\u0e25\u0e40\u0e25\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e25\u0e48\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e44\u0e14\u0e49\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e4830 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142001\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e2a\u0e22\u0e32\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142001 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e2a\u0e22\u0e32\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 300\/90  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e40\u0e1e\u0e25\u0e2a \u0e16\u0e19\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142028\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e04 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142028 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e04 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e01\u0e48\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 162\/70  \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142036\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e0a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142036 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e0a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 6 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142044\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e48\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142044 \u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e48\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e15\u0e4c \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u4e0d\u52d5\u7523 227\/224  \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142052\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e01 \u0e14\u0e2d\u0e17 \u0e44\u0e27\u0e17\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142052 \u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e01 \u0e14\u0e2d\u0e17 \u0e44\u0e27\u0e17\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 74109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2b\u0e25\u0e48\u0e2d \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30 oem \u0e41\u0e25\u0e30 odm \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19 \u0e44\u0e27\u0e19\u0e34\u0e25 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01 \u0e42\u0e25\u0e2b\u0e30 \u0e44\u0e21\u0e49 \u0e1c\u0e49\u0e32 \u0e22\u0e32\u0e07 \u0e0b\u0e34\u0e25\u0e34\u0e42\u0e04\u0e19 \u0e2d\u0e30\u0e04\u0e23\u0e34\u0e25\u0e34\u0e01 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e41\u0e01\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 537  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142079\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1b\u0e4a\u0e2d\u0e1b \u0e04\u0e25\u0e31\u0e1a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142079 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1b\u0e4a\u0e2d\u0e1b \u0e04\u0e25\u0e31\u0e1a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 260\/21  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142117\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e22\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e2e\u0e21 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142117 \u0e1a\u0e08.\u0e1a\u0e35 \u0e22\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e2e\u0e21 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 44\/100  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e25\u0e34\u0e28\u0e2d\u0e38\u0e1a\u0e25 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 52\u0e41\u0e22\u0e0145(\u0e21.\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e38\u0e1a\u0e25) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142133\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10752\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10752\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142133 \u0e1a\u0e08.\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 10752 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u88fd\u9020 159\/28  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2a\u0e19\u0e32\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 9 \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e41\u0e22\u0e01 60 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142150\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e42\u0e1a\u0e1f \u0e40\u0e14\u0e2d\u0e30 \u0e2a\u0e01\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142150 \u0e1a\u0e08.\u0e2d\u0e30\u0e42\u0e1a\u0e1f \u0e40\u0e14\u0e2d\u0e30 \u0e2a\u0e01\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e30 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c (contents) \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e1e\u0e23\u0e35\u0e40\u0e0b\u0e19\u0e40\u0e17\u0e0a\u0e31\u0e19 (presentation) \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e20\u0e32\u0e1e\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e07\u0e32\u0e19\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/280  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142168\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 (2022) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142168 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 (2022) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19  \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u5efa\u8a2d 33\/357  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e01 \u0e59 \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e01\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142176\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e1e\u0e47\u0e17 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142176 \u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e1e\u0e47\u0e17 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e02\u0e19\u0e21\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 12\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 4 \u0e41\u0e22\u0e01 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142184\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e34\u0e1f\u0e17\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142184 \u0e1a\u0e08.\u0e14\u0e23\u0e34\u0e1f\u0e17\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e21 \u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e42\u0e14\u0e19\u0e31\u0e17 \u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 45  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024823\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e01\u0e23\u0e2a\u0e0b\u0e35\u0e1f \u0e21\u0e31\u0e25\u0e15\u0e34\u0e1e\u0e25\u0e32\u0e22 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58191\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58191\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024823 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e01\u0e23\u0e2a\u0e0b\u0e35\u0e1f \u0e21\u0e31\u0e25\u0e15\u0e34\u0e1e\u0e25\u0e32\u0e22 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 58191 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e19\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e49\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 19\/278  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024831\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c \u0e1f\u0e2d\u0e23\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59129\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59129\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024831 \u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c \u0e1f\u0e2d\u0e23\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 59129 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e0b\u0e49\u0e33\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e15\u0e31\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e14\u0e35\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e44\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25\u0e04\u0e33\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e04\u0e33\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13 \u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e25\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e17\u0e1b \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e0b\u0e49\u0e33\u0e15\u0e49\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e40\u0e14\u0e34\u0e21\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e2a\u0e20\u0e32\u0e1e \u60c5\u5831\u901a\u4fe1\u30fbit 7\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024840\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e38\u0e2a\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024840 \u0e1a\u0e08.\u0e19\u0e38\u0e2a\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 998\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024866\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024866 \u0e1a\u0e08.\u0e19\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e27\u0e47\u0e1b\u0e44\u0e0b\u0e15\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/796  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024891\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024891 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e35\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04 (electronic business) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 188\/264  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024912\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e40\u0e21\u0e04\u0e04\u0e32\u0e19\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024912 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e40\u0e21\u0e04\u0e04\u0e32\u0e19\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 45\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e2b\u0e19\u0e32\u0e21\u0e41\u0e14\u0e07-\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35 27 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024921\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e1b\u0e19 \u0e42\u0e1b\u0e40\u0e15\u0e42\u0e15\u0e49 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024921 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e1b\u0e19 \u0e42\u0e1b\u0e40\u0e15\u0e42\u0e15\u0e49 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e21\u0e31\u0e19\u0e2b\u0e27\u0e32\u0e19\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19  \u0e21\u0e31\u0e19\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19  \u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024939\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024939 \u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41001 \u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 111\/152  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e19\u0e32\u0e25\u0e35 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c-\u0e2b\u0e19\u0e32\u0e21\u0e41\u0e14\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024947\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e02\u0e49\u0e32\u0e27\u0e21\u0e31\u0e19\u0e44\u0e01\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024947 \u0e1a\u0e08.\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e02\u0e49\u0e32\u0e27\u0e21\u0e31\u0e19\u0e44\u0e01\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e21\u0e31\u0e19\u0e44\u0e01\u0e48 \u0e44\u0e01\u0e48\u0e15\u0e49\u0e21 \u0e44\u0e01\u0e48\u0e17\u0e2d\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 (catering) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 (delivery) \u5bbf\u6cca\u30fb\u98f2\u98df 109  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024955\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e1e\u0e35 \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024955 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e1e\u0e35 \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e14\u0e39\u0e41\u0e25\u0e2d\u0e32\u0e23\u0e31\u0e01\u0e02\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 129\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024963\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e35\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024963 \u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e35\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u5efa\u8a2d 129\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024971\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e17\u0e35 \u0e40\u0e04 \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20131\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20131\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024971 \u0e1a\u0e08.\u0e17\u0e35 \u0e17\u0e35 \u0e40\u0e04 \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 20131 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e1a\u0e14\u0e22\u0e48\u0e2d\u0e22 \u0e1a\u0e14\u0e2d\u0e31\u0e14 \u0e2b\u0e25\u0e2d\u0e21 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e28\u0e29 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024980\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e48\u0e07\u0e44\u0e2b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024980 \u0e1a\u0e08.\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e48\u0e07\u0e44\u0e2b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 614  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569028110\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028110 \u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e21\u0e38\u0e14\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/83  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e0b\u0e2d\u0e22 \u0e41\u0e01\u0e49\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028128\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e1e \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028128 \u0e1a\u0e08.\u0e40\u0e17\u0e1e \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46105 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/567  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e25\u0e25\u0e14\u0e32 \u0e27\u0e07\u0e41\u0e27\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 4\/5 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e44\u0e1c\u0e48 \u0e2b\u0e19\u0e2d\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e07\u0e32\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028144\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21-\u0e40\u0e17\u0e04 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028144 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21-\u0e40\u0e17\u0e04 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e15\u0e48\u0e2d\u0e27\u0e07\u0e08\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5efa\u8a2d 49\/234  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028152\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2c\u0e32\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028152 \u0e1a\u0e08.\u0e40\u0e27\u0e2c\u0e32\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 11043 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 95\/139  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e17\u0e23\u0e31\u0e2a\u0e15\u0e4c \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028179\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e14\u0e23\u0e35\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028179 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e14\u0e23\u0e35\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 154\/135  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e20\u0e31\u0e2a\u0e2a\u0e23 51 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028187\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028187 \u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15  \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 165\/224  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028195\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e22\u0e41\u0e0a\u0e04 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028195 \u0e1a\u0e08.\u0e17\u0e2d\u0e22\u0e41\u0e0a\u0e04 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u6559\u80b2 9  \u0e0b\u0e2d\u0e22 \u0e40\u0e23\u0e27\u0e14\u0e35 38 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028217\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e35 \u0e17\u0e39\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028217 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e35 \u0e17\u0e39\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e17\u0e33\u0e42\u0e04\u0e23\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5efa\u8a2d 10\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028225\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e35\u0e21 \u0e2d\u0e35\u0e2a\u0e40\u0e17\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028225 \u0e1a\u0e08.\u0e20\u0e35\u0e21 \u0e2d\u0e35\u0e2a\u0e40\u0e17\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e23\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 84\/222  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028241\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028241 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 195\/193  \u0e0b\u0e2d\u0e22 \u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028250\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e0d\u0e0d\u0e4c\u0e13\u0e34\u0e0a\u0e32 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028250 \u0e1a\u0e08.\u0e01\u0e31\u0e0d\u0e0d\u0e4c\u0e13\u0e34\u0e0a\u0e32 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028276\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e19\u0e01\u0e27\u0e23\u0e23\u0e13 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23953\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23953\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028276 \u0e1a\u0e08.\u0e01\u0e19\u0e01\u0e27\u0e23\u0e23\u0e13 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 23953 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e17\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1c\u0e2a\u0e21\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e20 \u88fd\u9020 29\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028284\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 99 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29102\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29102\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028284 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 99 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 29102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c , \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e0a\u0e47\u0e04 , \u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 142  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e19\u0e19\u0e17\u0e4c 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002666\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08 \u0e19\u0e32\u0e27\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002666 \u0e2b\u0e08.\u0e40\u0e08 \u0e19\u0e32\u0e27\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-27 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27\/\u0e02\u0e19\u0e21\u0e2d\u0e1a\u0e01\u0e23\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 355\/386-387  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023231\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e32\u0e23\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023231 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e32\u0e23\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 80\/373-374  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023266\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023266 \u0e1a\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 88\/191  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023282\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023282 \u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 99\/244  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023291\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023291 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/117  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 7 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023304\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2d\u0e27\u0e4c\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023304 \u0e1a\u0e08.\u0e1e\u0e2d\u0e27\u0e4c\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e14\u0e39\u0e41\u0e25\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 2 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 14 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023312\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e0a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023312 \u0e1a\u0e08.\u0e27\u0e31\u0e0a\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111\/189  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e34\u0e42\u0e2d \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35-\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023321\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e25\u0e15\u0e34\u0e40\u0e25\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023321 \u0e1a\u0e08.\u0e21\u0e31\u0e25\u0e15\u0e34\u0e40\u0e25\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u60c5\u5831\u901a\u4fe1\u30fbit 400\/113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004938\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35.\u0e27\u0e34\u0e04\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004938 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35.\u0e27\u0e34\u0e04\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139\/532  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0155569000622\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e23\u0e37\u0e48\u0e19\u0e2a\u0e38\u0e02 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000622 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e23\u0e37\u0e48\u0e19\u0e2a\u0e38\u0e02 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 23\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0165569001769\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d \u0e23\u0e34\u0e19 89 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001769 \u0e1a\u0e08.\u0e2d\u0e2d \u0e23\u0e34\u0e19 89 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039129\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e19\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10303\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10303\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039129 \u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e19\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 10303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e49\u0e21 \u88fd\u9020 22\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039161\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e2a\u0e41\u0e15\u0e07 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039161 \u0e1a\u0e08.\u0e21\u0e31\u0e2a\u0e41\u0e15\u0e07 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 64201 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e25\u0e07\u0e17\u0e38\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e2d\u0e19\u0e2b\u0e38\u0e49\u0e19 \u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e49 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e2b\u0e19\u0e35\u0e49 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 40\/41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039170\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e34\u0e23\u0e31\u0e0d\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039170 \u0e1a\u0e08.\u0e2b\u0e34\u0e23\u0e31\u0e0d\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039196\",\"name_th\":\"\u0e1a\u0e08.\u0e1d\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19\u0e23\u0e16\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039196 \u0e1a\u0e08.\u0e1d\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19\u0e23\u0e16\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039200\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e14\u0e39\u0e42\u0e2d\u0e49\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039200 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e14\u0e39\u0e42\u0e2d\u0e49\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e14\u0e38\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 29\/57  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e31\u0e08\u0e08\u0e32 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039218\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74902\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74902\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039218 \u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 74902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e01\u0e33\u0e08\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 29\/79  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e13\u0e35\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e42\u0e2e\u0e21 \u0e1a\u0e48\u0e2d\u0e27\u0e34\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039226\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e20\u0e32 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039226 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e19\u0e20\u0e32 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 43901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e01\u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e1e\u0e37\u0e49\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19 \u0e1b\u0e39\u0e19 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e41\u0e23\u0e48 \u0e14\u0e35\u0e1a\u0e38\u0e01 \u0e02\u0e19\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e44\u0e1b\u0e17\u0e34\u0e49\u0e07  \u0e15\u0e25\u0e2d\u0e14\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e16\u0e21\u0e17\u0e35\u0e48 \u0e1a\u0e14\u0e2d\u0e31\u0e14\u0e14\u0e34\u0e19 \u0e40\u0e01\u0e25\u0e35\u0e48\u0e22\u0e14\u0e34\u0e19 \u5efa\u8a2d 121\/363  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039277\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46631\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46631\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039277 \u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46631 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 196\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039285\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e25\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039285 \u0e1a\u0e08.\u0e04\u0e2d\u0e25\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 444\/342  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e34 \u0e2d\u0e34\u0e19\u0e14\u0e35\u0e4a\u0e14 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e28\u0e23\u0e35\u0e23\u0e32\u0e0a\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039293\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e04\u0e2d\u0e19 \u0e08\u0e31\u0e21\u0e1e\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039293 \u0e1a\u0e08.\u0e21\u0e32\u0e04\u0e2d\u0e19 \u0e08\u0e31\u0e21\u0e1e\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e35\u0e27\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e2d\u0e35\u0e27\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 35\/3  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039307\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e16\u0e32\u0e27\u0e23 \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039307 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e16\u0e32\u0e27\u0e23 \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e02\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e01\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 445\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039323\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e42\u0e1a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039323 \u0e1a\u0e08.\u0e42\u0e23\u0e42\u0e1a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 106\/140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039331\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e01\u0e38 \u0e42\u0e0b\u0e01\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039331 \u0e1a\u0e08.\u0e42\u0e0b\u0e01\u0e38 \u0e42\u0e0b\u0e01\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e32\u0e22\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e48\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 29\/118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039340\",\"name_th\":\"\u0e1a\u0e08.\u0e1c\u0e39\u0e49\u0e01\u0e32\u0e23\u0e44\u0e01\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039340 \u0e1a\u0e08.\u0e1c\u0e39\u0e49\u0e01\u0e32\u0e23\u0e44\u0e01\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e01\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039358\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e27\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039358 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e27\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 66\/212  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e38\u0e02\u0e2a\u0e34\u0e23\u0e34 \u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039366\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e32 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039366 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e32 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 493\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039374\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e17\u0e23\u0e35\u0e21\u0e27\u0e2d\u0e0a (\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039374 \u0e1a\u0e08.\u0e2a\u0e17\u0e23\u0e35\u0e21\u0e27\u0e2d\u0e0a (\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e49\u0e32\u0e07\u0e08\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110\/147  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001375\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e14\u0e0b\u0e35\u0e48\u0e15\u0e33\u0e41\u0e15\u0e4a\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001375 \u0e2b\u0e08.\u0e21\u0e14\u0e0b\u0e35\u0e48\u0e15\u0e33\u0e41\u0e15\u0e4a\u0e14 2569-07-27 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e49\u0e21\u0e15\u0e33 \u0e23\u0e49\u0e32\u0e19\u0e22\u0e33 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 333\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009963\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04\u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009963 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04\u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569010007\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e40\u0e2d. \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010007 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e40\u0e2d. \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 17\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002365\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e2d\u0e40\u0e1b\u0e47\u0e01\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002365 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e2d\u0e40\u0e1b\u0e47\u0e01\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e27\u0e30 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u533b\u7642\u30fb\u798f\u7949 5\/17  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2a\u0e32\u0e22 9 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002373\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e0a\u0e34\u0e27 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002373 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e0a\u0e34\u0e27 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e30\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 55\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002381\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1b\u0e23\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002381 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1b\u0e23\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e01\u0e49\u0e27\u0e01\u0e32\u0e41\u0e1f\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e23\u0e31\u0e1a\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e42\u0e25\u0e42\u0e01\u0e49\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569002179\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e42\u0e21 \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002179 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e42\u0e21 \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u88fd\u9020 441\/178  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0275569001181\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e25\u0e21\u0e32\u0e15\u0e34\u0e01 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001181 \u0e1a\u0e08.\u0e42\u0e25\u0e21\u0e32\u0e15\u0e34\u0e01 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 408  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002991\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e32\u0e41\u0e15\u0e19\u0e34 \u0e42\u0e04\u0e25\u0e18\u0e34\u0e07\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002991 \u0e2b\u0e08.\u0e01\u0e32\u0e41\u0e15\u0e19\u0e34 \u0e42\u0e04\u0e25\u0e18\u0e34\u0e07 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569003008\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e19\u0e30 168 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569003008 \u0e2b\u0e08.\u0e0a\u0e19\u0e30 168 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-27 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 217  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007692\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e2a. \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007692 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e2a. \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 160\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007706\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e4a\u0e1f \u0e21\u0e35 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007706 \u0e1a\u0e08.\u0e01\u0e34\u0e4a\u0e1f \u0e21\u0e35 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1195\/24  \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007714\",\"name_th\":\"\u0e1a\u0e08. \u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 246 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007714 \u0e1a\u0e08. \u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 246 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u4e0d\u52d5\u7523 420  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007722\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e32\u0e23\u0e34\u0e01\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007722 \u0e1a\u0e08.\u0e28\u0e32\u0e23\u0e34\u0e01\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e32\u0e27\u0e1e\u0e25\u0e31\u0e2a\u0e44\u0e0b\u0e2a\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e04\u0e19\u0e2d\u0e49\u0e27\u0e19 \u0e0a\u0e38\u0e14\u0e40\u0e14\u0e23\u0e2a \u0e0a\u0e38\u0e14\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e0a\u0e38\u0e14\u0e25\u0e33\u0e25\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e15\u0e23\u0e35 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104\/3  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e 8 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569002038\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02 \u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569002038 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02 \u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46693 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0323569000602\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32 \u0e40\u0e0b\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33190\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33190\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000602 \u0e2b\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32 \u0e40\u0e0b\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-27 1000000 33190 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e15\u0e39\u0e49\u0e40\u0e0b\u0e1f\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u88fd\u9020 27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0345569003417\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003417 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 515  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003425\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003425 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003433\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e22\u0e22\u0e4c\u0e0d\u0e14\u0e32 \u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003433 \u0e1a\u0e08.\u0e2d\u0e31\u0e22\u0e22\u0e4c\u0e0d\u0e14\u0e32 \u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 242  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0353569000491\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e32\u0e22\u0e1e\u0e351989\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000491 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e32\u0e22\u0e1e\u0e351989 2569-07-27 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 660  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0353569000513\",\"name_th\":\"\u0e2b\u0e08.\u0e23.\u0e19\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c11 \u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000513 \u0e2b\u0e08.\u0e23.\u0e19\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c11 \u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-27 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 158  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0365569001503\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19 \u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001503 \u0e1a\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19 \u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e07\u0e32\u0e19\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0403569003341\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e17\u0e39\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003341 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e17\u0e39 2569-07-27 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u5bbf\u6cca\u30fb\u98f2\u98df 193  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007250\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007250 \u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e42\u0e17\u0e23\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 286  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007268\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e42\u0e22\u0e18\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007268 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e42\u0e22\u0e18\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 589\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007306\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e38\u0e4a\u0e01\u0e44\u0e01\u0e48\u0e2a\u0e49\u0e21\u0e15\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007306 \u0e1a\u0e08.\u0e01\u0e38\u0e4a\u0e01\u0e44\u0e01\u0e48\u0e2a\u0e49\u0e21\u0e15\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e49\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 285\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569004013\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e22\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004013 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e22\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e31\u0e1a?\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e23\u0e37\u0e2d \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569004021\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e27 \u0e1e\u0e25\u0e31\u0e2a\u0e44\u0e0b\u0e2a\u0e4c 69 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004021 \u0e1a\u0e08.\u0e2a\u0e32\u0e27 \u0e1e\u0e25\u0e31\u0e2a\u0e44\u0e0b\u0e2a\u0e4c 69 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e32\u0e27\u0e1e\u0e25\u0e31\u0e2a\u0e44\u0e0b\u0e15\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e04\u0e19\u0e2d\u0e49\u0e27\u0e19 \u0e0a\u0e38\u0e14\u0e40\u0e14\u0e23\u0e2a \u0e0a\u0e38\u0e14\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e0a\u0e38\u0e14\u0e25\u0e33\u0e25\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e15\u0e23\u0e35\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9849  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e28\u0e34\u0e23\u0e34\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e15\u0e23\u0e2d\u0e01\u0e17\u0e38\u0e48\u0e07\u0e18\u0e19\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0445569001791\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e38\u0e23\u0e21\u0e32 \u0e2e\u0e34\u0e0d\u0e32\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001791 \u0e1a\u0e08.\u0e19\u0e38\u0e23\u0e21\u0e32 \u0e2e\u0e34\u0e0d\u0e32\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e49\u0e32\u0e04\u0e25\u0e38\u0e21\u0e28\u0e35\u0e23\u0e29\u0e30\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21(\u0e2e\u0e34\u0e0d\u0e32\u0e1a) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07 \u0e01\u0e32\u0e22\u0e1c\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e49\u0e32\u0e15\u0e31\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001804\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e22 \u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001804 \u0e1a\u0e08.\u0e1a\u0e2d\u0e22 \u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47630 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e1b\u0e25\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e17\u0e34 \u0e04\u0e31\u0e19\u0e40\u0e1a\u0e47\u0e14 \u0e23\u0e2d\u0e01 \u0e2a\u0e32\u0e22\u0e40\u0e1a\u0e47\u0e14 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e2d\u0e21 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e08\u0e23\u0e34\u0e07 \u0e15\u0e31\u0e27\u0e40\u0e1a\u0e47\u0e14 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e1b\u0e25\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e34\u0e15\u0e34 \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0455569001588\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e01\u0e25\u0e49\u0e32\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001588 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e01\u0e25\u0e49\u0e32\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 311  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001596\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e34\u0e01\u0e32\u0e23\u0e4c17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55909\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55909\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001596 \u0e1a\u0e08.\u0e13\u0e34\u0e01\u0e32\u0e23\u0e4c17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 55909 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e2d\u0e19 \u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e15\u0e49\u0e19 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 170  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001600\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07 \u0e08\u0e47\u0e2d\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001600 \u0e1a\u0e08.\u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07 \u0e08\u0e47\u0e2d\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47630 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e1b\u0e25\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e04\u0e31\u0e19\u0e40\u0e1a\u0e47\u0e14 \u0e23\u0e2d\u0e01\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e2a\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19 \u0e2a\u0e32\u0e22\u0e1e\u0e35\u0e2d\u0e35 \u0e40\u0e1a\u0e47\u0e14\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e2d\u0e21 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e2a\u0e14 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e2b\u0e21\u0e31\u0e01  \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e16\u0e31\u0e07\u0e43\u0e2a\u0e48\u0e1b\u0e25\u0e32 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e43\u0e2a\u0e48\u0e04\u0e31\u0e19\u0e40\u0e1a\u0e47\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e04\u0e21\u0e1b\u0e4c\u0e1b\u0e34\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e.\u0e23.\u0e1a.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0473569001004\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e2a\u0e38\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569001004 \u0e2b\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e2a\u0e38\u0e01\u0e24\u0e29\u0e13\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-27 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 285  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001685\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e08\u0e48\u0e21\u0e08\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001685 \u0e1a\u0e08.\u0e41\u0e08\u0e48\u0e21\u0e08\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 25112 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u88fd\u9020 241  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32\u0e16\u0e48\u0e2d\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569001006\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e17\u0e35 \u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569001006 \u0e1a\u0e08.\u0e44\u0e2d\u0e17\u0e35 \u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e19\u0e49\u0e15\u0e1a\u0e38\u0e4a\u0e01 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e21\u0e32\u0e2a\u0e4c \u0e04\u0e35\u0e22\u0e4c\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e08\u0e2d\u0e20\u0e32\u0e1e \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e19\u0e31\u0e49\u0e19\u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0493569000423\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e32\u0e21\u0e1b\u0e49\u0e2d\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0493569000423 \u0e2b\u0e08.\u0e02\u0e32\u0e21\u0e1b\u0e49\u0e2d\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-27 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0515569001480\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e40\u0e17\u0e04 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001480 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e40\u0e17\u0e04 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e41\u0e01\u0e19\u0e08\u0e48\u0e32\u0e22\u0e04\u0e34\u0e27\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14 (qr code) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e31\u0e01 \u0e23\u0e49\u0e32\u0e19\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u5efa\u8a2d 193\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001790\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e25\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001790 \u0e1a\u0e08.\u0e19\u0e25\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e19\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e19\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u88fd\u9020 34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0533569000554\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0533569000554 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 2569-07-27 1000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e2a\u0e15\u0e17\u0e31\u0e28\u0e19\u0e39\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 297\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0573569002271\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e2b\u0e32\u0e1b\u0e2d\u0e19\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002271 \u0e2b\u0e08.\u0e21\u0e2b\u0e32\u0e1b\u0e2d\u0e19 2569-07-27 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2a\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e27\u0e31\u0e0a\u0e1e\u0e37\u0e0a (\u0e22\u0e32\u0e06\u0e48\u0e32\u0e2b\u0e0d\u0e49\u0e32) \u0e2a\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07 \u0e2a\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e33\u0e08\u0e31\u0e14\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e2a\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e42\u0e23\u0e04\u0e1e\u0e37\u0e0a \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004861\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e40\u0e17\u0e48\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004861 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e40\u0e17\u0e48\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 563\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001762\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e42\u0e2d\u0e27\u0e32\u0e22\u0e27\u0e32\u0e22\u0e17\u0e35\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001762 \u0e2b\u0e08.\u0e40\u0e04\u0e42\u0e2d\u0e27\u0e32\u0e22\u0e27\u0e32\u0e22\u0e17\u0e35 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001771\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001771 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35 2569-07-27 1000000 47640 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001789\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e47\u0e01\u0e14\u0e35\u0e42\u0e21\u0e1a\u0e32\u0e22\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001789 \u0e2b\u0e08.\u0e40\u0e14\u0e47\u0e01\u0e14\u0e35\u0e42\u0e21\u0e1a\u0e32\u0e22 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001797\",\"name_th\":\"\u0e2b\u0e08.345 \u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001797 \u0e2b\u0e08.345 \u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19 2569-07-27 1000000 47640 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002213\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002213 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 8\/133  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0615569000610\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e23\u0e48\u0e40\u0e21\u0e32\u0e40\u0e17\u0e48\u0e19\u0e27\u0e34\u0e27 \u0e17\u0e23\u0e2d\u0e1e\u0e1e\u0e34\u0e40\u0e04\u0e34\u0e25 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55103\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55103\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000610 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e23\u0e48\u0e40\u0e21\u0e32\u0e40\u0e17\u0e48\u0e19\u0e27\u0e34\u0e27 \u0e17\u0e23\u0e2d\u0e1e\u0e1e\u0e34\u0e40\u0e04\u0e34\u0e25 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 55103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0635569001535\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e41\u0e2a\u0e07\u0e17\u0e2d\u0e07 \u0e2d\u0e35-\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001535 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e41\u0e2a\u0e07\u0e17\u0e2d\u0e07 \u0e2d\u0e35-\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c ( e-commerce ) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c ( social media ) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/30  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e41\u0e23\u0e071 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002426\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e1f 789 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002426 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e1f 789 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c  \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 79\/13  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0665569000733\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000733 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32 \u0e21\u0e35 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e15\u0e25\u0e2d\u0e14\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e40\u0e23\u0e14\u0e32\u0e23\u0e4c \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e22\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e39\u0e49\u0e2a\u0e32\u0e02\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e08\u0e32\u0e01\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e27\u0e21\u0e2b\u0e39 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e42\u0e17\u0e23\u0e40\u0e25\u0e02 \u0e42\u0e17\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e42\u0e17\u0e23\u0e20\u0e32\u0e1e \u0e42\u0e17\u0e23\u0e2a\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e08\u0e32\u0e19\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e27\u0e34\u0e17\u0e22\u0e38\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0675569001608\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e32\u0e27 \u0e1a\u0e25\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001608 \u0e1a\u0e08.\u0e1e\u0e23\u0e32\u0e27 \u0e1a\u0e25\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 11041 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003430\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e0a \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003430 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e0a \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 01139 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e25\u0e39\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u8fb2\u6797\u6c34\u7523 31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002816\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002816 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e16\u0e19\u0e19\u0e2d\u0e39\u0e48\u0e17\u0e2d\u0e07 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002824\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002824 \u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46900 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e48\u0e07-\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1045  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002832\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d 168 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002832 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d 168 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 66\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002239\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002239 \u0e1a\u0e08.\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e19\u0e34\u0e27\u0e40\u0e21\u0e15\u0e34\u0e01 \u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e01 \u0e27\u0e32\u0e25\u0e4c\u0e27 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 37\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007583\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e1b\u0e1e\u0e34\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007583 \u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e1b\u0e1e\u0e34\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 99\/55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007591\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e2d\u0e23\u0e38\u0e13\u0e07\u0e32\u0e21\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007591 \u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e2d\u0e23\u0e38\u0e13\u0e07\u0e32\u0e21\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e14\u0e1e\u0e30\u0e42\u0e25\u0e49 \u0e40\u0e1b\u0e47\u0e14\u0e22\u0e48\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007605\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007605 \u0e1a\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 7\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007630\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e44\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007630 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e44\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007648\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e19\u0e35\u0e48\u0e44\u0e17\u0e21\u0e4c \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007648 \u0e1a\u0e08.\u0e40\u0e2d\u0e19\u0e35\u0e48\u0e44\u0e17\u0e21\u0e4c \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e28\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 68\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007991\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e47\u0e21  \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"61101\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"61101\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007991 \u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e47\u0e21  \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 61101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e1a\u0e1a\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 115\/353  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569008016\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45402\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45402\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008016 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 45402 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e1b\u0e31\u0e4a\u0e21\u0e40\u0e1a\u0e23\u0e04\u0e1a\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e32\u0e07\u0e41\u0e1f\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121\/18,121\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0755569000562\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e31\u0e1a\u0e17\u0e34\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e39\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66301\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66301\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0755569000562 \u0e1a\u0e08.\u0e17\u0e31\u0e1a\u0e17\u0e34\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e39\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 66301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e34\u0e40\u0e23\u0e34\u0e48\u0e21 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1c\u0e39\u0e49\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e23\u0e27\u0e21 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e23\u0e27\u0e21\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e23\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e17\u0e23\u0e31\u0e2a\u0e15\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c(reit) \u0e41\u0e25\u0e30\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u91d1\u878d\u30fb\u4fdd\u967a 35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0765569001526\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e41\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001526 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e41\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 226\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569003162\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 2533 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003162 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 2533 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e48\u0e2d\u0e04\u0e49\u0e32\u0e04\u0e19\u0e01\u0e25\u0e32\u0e07\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e38\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e38\u0e49\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002939\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002939 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e33 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 271  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002947\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e40\u0e27\u0e17 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002947 \u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e40\u0e27\u0e17 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 29\/40-41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0815569002246\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e2d\u0e30\u0e01\u0e23\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002246 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e2d\u0e30\u0e01\u0e23\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e01\u0e32\u0e01\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e41\u0e25\u0e30\u0e01\u0e30\u0e25\u0e32\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0815569002254\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e21\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002254 \u0e1a\u0e08.\u0e20\u0e39\u0e21\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 131\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0815569002262\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35 \u0e14\u0e35\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002262 \u0e1a\u0e08.\u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35 \u0e14\u0e35\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e0a\u0e38\u0e14\u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e2a\u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569013795\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e15\u0e15\u0e49\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013795 \u0e1a\u0e08.\u0e1e\u0e34\u0e15\u0e15\u0e49\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 59\/90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013809\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e04\u0e31\u0e17\u0e0b\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013809 \u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e04\u0e31\u0e17\u0e0b\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e0b\u0e2d\u0e22\u0e1c\u0e21 \u0e2a\u0e23\u0e30\u0e1c\u0e21 \u0e14\u0e31\u0e14\u0e1c\u0e21 \u0e22\u0e49\u0e2d\u0e21\u0e1c\u0e21 \u0e17\u0e33\u0e2a\u0e35\u0e1c\u0e21 \u0e22\u0e37\u0e14\u0e1c\u0e21 \u0e2d\u0e1a\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e23\u0e07\u0e1c\u0e21  \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 95\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010923\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e04\u0e42\u0e04 \u0e01\u0e23\u0e38\u0e4a\u0e1b 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010923 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e04\u0e42\u0e04 \u0e01\u0e23\u0e38\u0e4a\u0e1b 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e19\u0e49\u0e33\u0e01\u0e30\u0e17\u0e34 \u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 236\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e2d\u0e33\u0e40\u0e20\u0e2d \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010931\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010931 \u0e1a\u0e08.\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 151  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0865569001312\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0a \u0e2d\u0e38\u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001312 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0a \u0e2d\u0e38\u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001794\",\"name_th\":\"\u0e2b\u0e08.\u0e0a \u0e0a\u0e31\u0e22\u0e27\u0e31\u0e12\u0e19\u0e4c  9998\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001794 \u0e2b\u0e08.\u0e0a \u0e0a\u0e31\u0e22\u0e27\u0e31\u0e12\u0e19\u0e4c  9998 2569-07-27 1000000 46204 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e01\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001816\",\"name_th\":\"\u0e2b\u0e08.3\u0e40\u0e2d\u0e2a \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001816 \u0e2b\u0e08.3\u0e40\u0e2d\u0e2a \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-27 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e19\u0e49\u0e33 \u0e07\u0e32\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u5efa\u8a2d 59\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001824\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e27\u0e25\u0e34\u0e13 \u0e41\u0e21\u0e0a\u0e0a\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001824 \u0e2b\u0e08.\u0e40\u0e01\u0e27\u0e25\u0e34\u0e13 \u0e41\u0e21\u0e0a\u0e0a\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 2569-07-27 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 299\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e0a\u0e0e\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006313\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e34\u0e2b\u0e25\u0e32 \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006313 \u0e1a\u0e08.\u0e2a\u0e21\u0e34\u0e2b\u0e25\u0e32 \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 99\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006321\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e30\u0e19\u0e30 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006321 \u0e1a\u0e08.\u0e08\u0e30\u0e19\u0e30 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 60\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006348\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e27\u0e32\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006348 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e27\u0e32\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e40\u0e1a\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e39\u0e17 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e04\u0e25\u0e38\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e41\u0e08\u0e47\u0e04\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22  \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e15\u0e23\u0e35 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e.\u0e23.\u0e1a.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110  \u0e0b\u0e2d\u0e22 4(\u0e42\u0e0a\u0e04\u0e2a\u0e21\u0e32\u0e195) \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0963569000330\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e34\u0e19\u0e2e\u0e31\u0e2a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000330 \u0e2b\u0e08.\u0e1a\u0e34\u0e19\u0e2e\u0e31\u0e2a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-27 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569141285\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2e\u0e25\u0e40\u0e21\u0e48\u0e2a\u0e4c\u0e40\u0e2e\u0e07\u0e40\u0e2e\u0e07\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96305\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96305\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141285 \u0e1a\u0e08.\u0e42\u0e2e\u0e25\u0e40\u0e21\u0e48\u0e2a\u0e4c\u0e40\u0e2e\u0e07\u0e40\u0e2e\u0e07\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 96305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 563\/6  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141293\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141293 \u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 42901 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u5efa\u8a2d 2\/13  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2\/13 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 25 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141307\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e2d\u0e35\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141307 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e2d\u0e35\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 219\/47  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 47 \u0e41\u0e22\u0e01 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141315\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e08\u0e4b \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141315 \u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e08\u0e4b \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/4  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 80 \u0e41\u0e22\u0e01 22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141323\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e25\u0e27\u0e32 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141323 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e25\u0e27\u0e32 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 755 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141331\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e44\u0e27\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141331 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e44\u0e27\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1213\/481  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 94 (\u0e1b\u0e31\u0e0d\u0e08\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024815\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e1b\u0e40\u0e17\u0e04 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024815 \u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e1b\u0e40\u0e17\u0e04 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 interactive \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 iot, \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30,website, hardware, software \u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e40\u0e01\u0e21\u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e0a\u0e34\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 201\/779  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569023169\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39 \u0e1b\u0e23\u0e32\u0e0a\u0e0d\u0e4c\u0e1b\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47811\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47811\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023169 \u0e1a\u0e08.\u0e22\u0e39 \u0e1b\u0e23\u0e32\u0e0a\u0e0d\u0e4c\u0e1b\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 47811 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07  \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004920\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e0a\u0e15 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e42\u0e04\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004920 \u0e1a\u0e08.\u0e23\u0e0a\u0e15 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e42\u0e04\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222\/304  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e4c\u0e25\u0e48\u0e32 \u0e1e\u0e2d\u0e0a\u0e0a\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 14\u0e40\u0e2d \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0203569003301\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e39\u0e0a\u0e35\u0e1e \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003301 \u0e2b\u0e08.\u0e0a\u0e39\u0e0a\u0e35\u0e1e \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c 2569-07-26 1000000 25111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u88fd\u9020 71\/435  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 71 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039081\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039081 \u0e1a\u0e08.\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 49334 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 292\/47  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e42\u0e2e\u0e21 \u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039099\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039099 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3\/2  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e1e\u0e31\u0e12\u0e19\u0e32 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039102\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e34\u0e04\u0e32\u0e42\u0e23\u0e30 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039102 \u0e1a\u0e08.\u0e2e\u0e34\u0e04\u0e32\u0e42\u0e23\u0e30 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e25\u0e32\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 apple app store, google play store \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 1\/111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002958\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e0b\u0e2d\u0e1f\u0e15\u0e4c \u0e1a\u0e35\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002958 \u0e2b\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e0b\u0e2d\u0e1f\u0e15\u0e4c \u0e1a\u0e35 2569-07-26 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 281\/3  \u0e0b\u0e2d\u0e22 \u0e40\u0e14\u0e0a\u0e2d\u0e38\u0e14\u0e21 14 \u0e16\u0e19\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0405569007241\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007241 \u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 47593 \u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0735569007575\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e07\u0e27\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e23\u0e34\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007575 \u0e1a\u0e08.\u0e2a\u0e07\u0e27\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e23\u0e34\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 31\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0775569003154\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003154 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e04\u0e19\u0e40\u0e01\u0e29\u0e35\u0e22\u0e13 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 14\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0963569000321\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e2a\u0e34\u0e01 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000321 \u0e2b\u0e08.\u0e21\u0e32\u0e2a\u0e34\u0e01 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-26 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 135  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569008087\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008087 \u0e2b\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 2569-07-25 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 20  \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140998\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e48\u0e32 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140998 \u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e48\u0e32 \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/259  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e1f \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e014 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141005\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e21\u0e39\u0e23\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141005 \u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e21\u0e39\u0e23\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 298\/555  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e27\u0e2d\u0e40\u0e23\u0e19\u0e14\u0e49\u0e32 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 555 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141021\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e31\u0e21\u0e40\u0e1a\u0e34\u0e25\u0e42\u0e1a\u0e25\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141021 \u0e1a\u0e08.\u0e2e\u0e31\u0e21\u0e40\u0e1a\u0e34\u0e25\u0e42\u0e1a\u0e25\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e20\u0e32\u0e1e\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 244\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 5 \u0e41\u0e22\u0e01 3 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141030\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e04 \u0e2e\u0e32\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141030 \u0e1a\u0e08.\u0e40\u0e17\u0e04 \u0e2e\u0e32\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e32\u0e07 \u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/155  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e0b\u0e35\u0e1e\u0e32\u0e23\u0e4c\u0e04\u0e27\u0e34\u0e27 3 \u0e0b\u0e2d\u0e22 \u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c 34\/1 \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141064\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d.\u0e25\u0e34\u0e2a\u0e15\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e17\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141064 \u0e1a\u0e08.\u0e40\u0e2d.\u0e25\u0e34\u0e2a\u0e15\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e17\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 999\/92  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e2a\u0e34\u0e23\u0e34 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e34 \u0e16\u0e19\u0e1901 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141072\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e0b \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141072 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e0b \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 343\/319  \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e25\u0e33\u0e40\u0e08\u0e35\u0e22\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141081\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141081 \u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 595\/34  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e22\u0e23\u0e32\u0e21\u0e31\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141111\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e19\u0e15\u0e4c \u0e17\u0e47\u0e2d\u0e1b \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141111 \u0e1a\u0e08.\u0e40\u0e23\u0e19\u0e15\u0e4c \u0e17\u0e47\u0e2d\u0e1b \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 50\/3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141129\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e17\u0e35 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141129 \u0e1a\u0e08.\u0e08\u0e35\u0e17\u0e35 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3-33 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 66\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141153\",\"name_th\":\"\u0e1a\u0e08.1981 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141153 \u0e1a\u0e08.1981 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e23\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 956  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e2d\u0e14\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141170\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141170 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e41\u0e2d\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 49\/610  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 39 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141200\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e21\u0e39\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141200 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e21\u0e39\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 18\/5  \u0e0b\u0e2d\u0e22 \u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e41\u0e01\u0e49\u0e274 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024751\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024751 \u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47190 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71\/77  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e01\u0e21.10 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e0b\u0e2d\u0e22 \u0e21\u0e2b\u0e32\u0e0a\u0e31\u0e22 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024777\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e27\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024777 \u0e1a\u0e08.\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e27\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 109\/554-557  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32\u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024807\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e1a\u0e41\u0e14\u0e07\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e2a \u0e0b\u0e34\u0e19\u0e2a\u0e4c 2002 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024807 \u0e1a\u0e08.\u0e0b\u0e31\u0e1a\u0e41\u0e14\u0e07\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e2a \u0e0b\u0e34\u0e19\u0e2a\u0e4c 2002 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 9\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569028071\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e23\u0e34\u0e40\u0e2d\u0e19 \u0e44\u0e2d\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028071 \u0e1a\u0e08.\u0e25\u0e2d\u0e23\u0e34\u0e40\u0e2d\u0e19 \u0e44\u0e2d\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 (body oil) \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1c\u0e34\u0e27 (cleansing oil) \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 (shower oil) \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 99\/120  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e2a\u0e34\u0e01\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028101\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028101 \u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e1a\u0e1a\u0e25\u0e34\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023118\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e42\u0e1f\u0e23\u0e4c \u0e23\u0e34\u0e0a 9 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023118 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e42\u0e1f\u0e23\u0e4c \u0e23\u0e34\u0e0a 9 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/241  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004911\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0b\u0e31\u0e48\u0e19 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28221\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28221\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004911 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0b\u0e31\u0e48\u0e19 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 28221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e25\u0e36\u0e07 \u0e01\u0e31\u0e14 \u0e40\u0e08\u0e32\u0e30 \u0e04\u0e27\u0e49\u0e32\u0e19 \u0e40\u0e08\u0e35\u0e22\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19 machining \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 cnc \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 125\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0195569002692\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e27\u0e2d\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e2a\u0e40\u0e04\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002692 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e27\u0e2d\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e2a\u0e40\u0e04\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e40\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e34\u0e10\u0e1a\u0e25\u0e47\u0e2d\u0e01 \u0e15\u0e31\u0e27\u0e2b\u0e19\u0e2d\u0e19 \u0e2b\u0e34\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e27\u0e19 \u0e15\u0e38\u0e4a\u0e01\u0e15\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e27\u0e19  \u0e17\u0e23\u0e32\u0e22 \u0e1b\u0e39\u0e19  \u0e2a\u0e35\u0e17\u0e32\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e1b\u0e39\u0e19\u0e01\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039005\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e17\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039005 \u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e17\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46421 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 315\/1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039013\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e48\u0e1a\u0e2a\u0e30\u0e14\u0e38\u0e49\u0e07\u0e25\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039013 \u0e1a\u0e08.\u0e41\u0e0b\u0e48\u0e1a\u0e2a\u0e30\u0e14\u0e38\u0e49\u0e07\u0e25\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 168\/132  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e25\u0e30\u0e21\u0e38\u0e07 19 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039021\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e23\u0e39\u0e17 \u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039021 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e23\u0e39\u0e17 \u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07 (customs broker) \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e01\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 79\/293  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039048\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039048 \u0e1a\u0e08.\u0e21\u0e34\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e44\u0e27\u0e19\u0e34\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039064\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039064 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 43210 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 ev \u5efa\u8a2d 19\/141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039072\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e48\u0e32 \u0e2d\u0e35\u0e2a\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e1e\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20231\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20231\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039072 \u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e48\u0e32 \u0e2d\u0e35\u0e2a\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e1e\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 20231 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u88fd\u9020 660\/38  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e31\u0e19\u0e17\u0e23\u0e35\u0e2e\u0e34\u0e25\u0e25\u0e4c \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009939\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e42\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009939 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e42\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e1e \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e15\u0e48\u0e32\u0e07\u0e46\u0e43\u0e19\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u5efa\u8a2d 12\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569004058\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e25\u0e32\u0e07\u0e41\u0e1a\u0e1a \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004058 \u0e1a\u0e08.\u0e01\u0e25\u0e32\u0e07\u0e41\u0e1a\u0e1a \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e19\u0e34\u0e01 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 125\/144  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e42\u0e2a\u0e18\u0e23 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0365569001490\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001490 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 412  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0405569007233\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e42\u0e2e\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007233 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e42\u0e2e\u0e21\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32  \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2a\u0e27\u0e19  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e43\u0e2a\u0e48\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e1a\u0e39\u0e17 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569004005\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35.\u0e40\u0e04.\u0e42\u0e21\u0e42\u0e15\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45402\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45402\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004005 \u0e1a\u0e08.\u0e0b\u0e35.\u0e40\u0e04.\u0e42\u0e21\u0e42\u0e15\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 45402 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e07 \u0e25\u0e49\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 65-65\/1-2  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e31\u0e01\u0e29\u0e4c\u0e28\u0e34\u0e25\u0e1b\u0e32\u0e04\u0e21 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0425569000590\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e21\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47742\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47742\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000590 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e21\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 47742 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0445569001774\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a-\u0e1e\u0e25\u0e31\u0e2a \u0e23\u0e34\u0e0a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001774 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a-\u0e1e\u0e25\u0e31\u0e2a \u0e23\u0e34\u0e0a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0503569005220\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e15\u0e35\u0e22\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005220 \u0e2b\u0e08.\u0e40\u0e15\u0e35\u0e22\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25 2569-07-25 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 47\/37  \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e15\u0e19\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016738\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35-\u0e41\u0e27\u0e1a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016738 \u0e1a\u0e08.\u0e08\u0e35-\u0e41\u0e27\u0e1a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001773\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e0a\u0e23 \u0e44\u0e1a\u0e42\u0e2d\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001773 \u0e1a\u0e08.\u0e1e\u0e0a\u0e23 \u0e44\u0e1a\u0e42\u0e2d\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122\/7  \u0e16\u0e19\u0e19\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004853\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e09\u0e35\u0e22\u0e19\u0e40\u0e09\u0e35\u0e22\u0e19 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004853 \u0e1a\u0e08.\u0e40\u0e09\u0e35\u0e22\u0e19\u0e40\u0e09\u0e35\u0e22\u0e19 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 420  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0665569000725\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e01 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000725 \u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e01 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e44\u0e01\u0e48\u0e40\u0e19\u0e37\u0e49\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0735569007541\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e0d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007541 \u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e0d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e39\u0e48\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (digital & ai transformation) \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 34\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007559\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007559 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e39\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 188\/454  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e48 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21-\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007567\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e19\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007567 \u0e1a\u0e08.\u0e19\u0e32\u0e19\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007982\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e27\u0e35 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007982 \u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e27\u0e35 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e23\u0e31\u0e49\u0e27 \u0e40\u0e2a\u0e32\u0e44\u0e1f \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 38\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0755569000554\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e29\u0e32\u0e44\u0e17\u0e22\u0e42\u0e04\u0e42\u0e04\u0e48\u0e19\u0e31\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0755569000554 \u0e1a\u0e08.\u0e40\u0e21\u0e29\u0e32\u0e44\u0e17\u0e22\u0e42\u0e04\u0e42\u0e04\u0e48\u0e19\u0e31\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46313 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e49\u0e07\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32-\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e02\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e02\u0e32\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e02\u0e32\u0e22\u0e1c\u0e34\u0e27\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e02\u0e32\u0e22\u0e01\u0e30\u0e25\u0e32\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e02\u0e32\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e22\u0e01\u0e25\u0e39\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0805569002912\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e0b\u0e35\u0e25\u0e32\u0e22\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002912 \u0e1a\u0e08.\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u0e0b\u0e35\u0e25\u0e32\u0e22\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 23999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e42\u0e25\u0e2b\u0e30\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e23\u0e35\u0e14\u0e40\u0e22\u0e47\u0e19 \u88fd\u9020 66\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0845569010885\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e01.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010885 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e01.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 49\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010907\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e1a\u0e35 \u0e21\u0e27\u0e22\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010907 \u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e1a\u0e35 \u0e21\u0e27\u0e22\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e22\u0e34\u0e21\u0e21\u0e27\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e31\u0e01\u0e29\u0e30\u0e21\u0e27\u0e22 \u6559\u80b2 71\/163  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569006232\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f \u0e42\u0e2d \u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e2d\u0e25 \u0e0b\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01469\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01469\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006232 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f \u0e42\u0e2d \u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e2d\u0e25 \u0e0b\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 01469 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u8fb2\u6797\u6c34\u7523 58\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006241\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006241 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e25\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e23\u0e27\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 445\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006259\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006259 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006267\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e14\u0e19\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006267 \u0e1a\u0e08.\u0e41\u0e14\u0e19\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006275\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49331\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49331\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006275 \u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 49331 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 69\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0915569000374\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e41\u0e1e\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01302\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01302\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0915569000374 \u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e41\u0e1e\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 1000000 01302 \u0e40\u0e1e\u0e32\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u8fb2\u6797\u6c34\u7523 102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569008028\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35 1982\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47111\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47111\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008028 \u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35 1982 2569-07-24 1000000 47111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 481\/374  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569008061\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e34\u0e19\u0e14\u0e35\u0e49\u0e41\u0e04\u0e23\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008061 \u0e2b\u0e08.\u0e04\u0e34\u0e19\u0e14\u0e35\u0e49\u0e41\u0e04\u0e23\u0e4c 2569-07-24 1000000 46900 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b\u0e2d\u0e22 7 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139639\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e15\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139639 \u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e15\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 104\/128  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e2d-\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139647\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e32\u0e01\u0e49\u0e2d\u0e19\u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139647 \u0e1a\u0e08.\u0e14\u0e23\u0e32\u0e01\u0e49\u0e2d\u0e19\u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 56 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139655\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139655 \u0e1a\u0e08.\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 (oem\/odm) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 158  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139663\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e18\u0e19\u0e17\u0e34\u0e04 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47742\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47742\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139663 \u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e18\u0e19\u0e17\u0e34\u0e04 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47742 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21\u0e41\u0e17\u0e49\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1111\/54  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139698\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e39\u0e2a\u0e17\u0e4c\u0e2d\u0e31\u0e1e \u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139698 \u0e1a\u0e08.\u0e1a\u0e39\u0e2a\u0e17\u0e4c\u0e2d\u0e31\u0e1e \u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23  \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 40  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 50\/3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139701\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32\u0e1a\u0e32\u0e23\u0e21\u0e35\u0e1f\u0e39\u0e49\u0e14 789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139701 \u0e1a\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32\u0e1a\u0e32\u0e23\u0e21\u0e35\u0e1f\u0e39\u0e49\u0e14 789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 1473  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139710\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e0a\u0e35\u0e22\u0e2a \u0e40\u0e1e\u0e47\u0e17 \u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e40\u0e19\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139710 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e0a\u0e35\u0e22\u0e2a \u0e40\u0e1e\u0e47\u0e17 \u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e40\u0e19\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/96  \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139736\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139736 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 108  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e40\u0e01\u0e49\u0e3247 (\u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e356) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139779\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19 \u0e2a\u0e40\u0e1b\u0e0a \u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e2b\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139779 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19 \u0e2a\u0e40\u0e1b\u0e0a \u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e2b\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e39\u0e2b\u0e32\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e41\u0e2b\u0e48\u0e07 \u5efa\u8a2d 61\/371  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e27\u0e34\u0e19\u0e17\u0e27\u0e07\u0e28\u0e4c 44 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139795\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e41\u0e27\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139795 \u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e41\u0e27\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 230\/9  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139809\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e19\u0e4c \u0e40\u0e19\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47221\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47221\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139809 \u0e1a\u0e08.\u0e44\u0e27\u0e19\u0e4c \u0e40\u0e19\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e27\u0e19\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e41\u0e0a\u0e21\u0e40\u0e1b\u0e0d \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/6  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139817\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e17\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139817 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e17\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence: ai) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49 \u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e0a\u0e17\u0e1a\u0e2d\u0e17 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e15\u0e31\u0e27\u0e25\u0e30\u0e04\u0e23\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07 (virtual character) \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e40\u0e0a\u0e34\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c (generative ai) \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e20\u0e32\u0e1e \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e41\u0e25\u0e30 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1d\u0e36\u0e01\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07 (fine-tuning) \u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data processing) \u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai models) \u0e0a\u0e38\u0e14\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (datasets) \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e41\u0e25\u0e30 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 10  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 100 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139825\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e15\u0e34\u0e21\u0e2a\u0e38\u0e02 (\u0e44\u0e21\u0e48) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139825 \u0e1a\u0e08.\u0e40\u0e15\u0e34\u0e21\u0e2a\u0e38\u0e02 (\u0e44\u0e21\u0e48) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e2a\u0e01\u0e39\u0e4a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139833\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e19\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25113\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25113\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139833 \u0e1a\u0e08.\u0e1a\u0e32\u0e19\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 25113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e25\u0e39\u0e01\u0e25\u0e49\u0e2d\u0e1a\u0e32\u0e19\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u88fd\u9020 49  \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e2f \u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d 10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139841\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139841 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1f\u0e23\u0e19\u0e44\u0e0b\u0e2a\u0e4c\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 359\/7  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 50 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139876\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e40\u0e1e\u0e25\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139876 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e40\u0e1e\u0e25\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 8  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 46\/3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139884\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e41\u0e1a\u0e47\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139884 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e41\u0e1a\u0e47\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 287-289  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e31\u0e16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139906\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e42\u0e04\u0e40\u0e17\u0e04 1994 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139906 \u0e1a\u0e08.\u0e40\u0e21\u0e42\u0e04\u0e40\u0e17\u0e04 1994 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105\/296  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139914\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e1b\u0e14\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139914 \u0e1a\u0e08.\u0e41\u0e2d\u0e1b\u0e14\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (software) \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 (mobile application) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 iot \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e20\u0e39\u0e21\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c (gis) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 35\/27  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e31\u0e2a\u0e04\u0e32\u0e19\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e0837 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139922\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e08\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139922 \u0e1a\u0e08.\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e08\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 47\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e04\u0e39\u0e49\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e34\u0e1a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139931\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e32\u0e25\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139931 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e32\u0e25\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 570\/441  \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139965\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e22\u0e4c \u0e44\u0e19\u0e17\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139965 \u0e1a\u0e08.\u0e40\u0e14\u0e22\u0e4c \u0e44\u0e19\u0e17\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e27\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 38  \u0e0b\u0e2d\u0e22 \u0e42\u0e01\u0e2a\u0e38\u0e21\u0e23\u0e27\u0e21\u0e43\u0e08 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139973\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e1e\u0e47\u0e17\u0e40\u0e27\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139973 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e1e\u0e47\u0e17\u0e40\u0e27\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e02\u0e19\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e14\u0e39\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/112  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e27\u0e19\u0e34\u0e27 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139981\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139981 \u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c (solar cell) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 76\/238  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e27\u0e34\u0e19\u0e17\u0e27\u0e07\u0e28\u0e4c 64 (\u0e41\u0e01\u0e49\u0e27\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140009\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e19\u0e2a\u0e4c\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140009 \u0e1a\u0e08.\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e19\u0e2a\u0e4c\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e27\u0e35\u0e14\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c  \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e2a\u0e37\u0e48\u0e2d\u0e41\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e17\u0e32\u0e07\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e38 \u0e42\u0e23\u0e07\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 15  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e08\u0e39\u0e23\u0e35\u0e48 \u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e39\u0e1f\u0e27\u0e35\u0e48 \u0e1e\u0e25\u0e32\u0e0b\u0e48\u0e32 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140017\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e25\u0e1f\u0e4c \u0e40\u0e2d\u0e14\u0e08\u0e4c \u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 03 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140017 \u0e1a\u0e08.\u0e01\u0e31\u0e25\u0e1f\u0e4c \u0e40\u0e2d\u0e14\u0e08\u0e4c \u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 03 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 63112 \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e42\u0e2d\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data center) \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e14\u0e35\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e28\u0e39\u0e19\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e22\u0e48\u0e2d\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e27\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22 (server co-location) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 (co-location) \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e22\u0e48\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e39\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e40\u0e2b\u0e15\u0e38\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 87  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e17\u0e22 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e25\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140025\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e1e\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140025 \u0e1a\u0e08.\u0e42\u0e2d\u0e1e\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e1c\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar panel) \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e38 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e23\u0e30\u0e1a\u0e1a \u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e41\u0e25\u0e30 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 1589\/173  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e233 \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 63 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140033\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e25\u0e1f\u0e4c \u0e40\u0e2d\u0e14\u0e08\u0e4c \u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140033 \u0e1a\u0e08.\u0e01\u0e31\u0e25\u0e1f\u0e4c \u0e40\u0e2d\u0e14\u0e08\u0e4c \u0e14\u0e32\u0e15\u0e49\u0e32 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 63112 \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e42\u0e2d\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data center) \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e14\u0e35\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e28\u0e39\u0e19\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e22\u0e48\u0e2d\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e27\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22 (server co-location) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 (co-location) \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e22\u0e48\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e39\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e40\u0e2b\u0e15\u0e38\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 87  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e17\u0e22 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 \u0e40\u0e1e\u0e25\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140084\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e17\u0e35 \u0e41\u0e27\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52101\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52101\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140084 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e17\u0e35 \u0e41\u0e27\u0e23\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 52101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e42\u0e01\u0e14\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47\u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a \u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e49\u0e27 \u904b\u8f38\u30fb\u7269\u6d41 36  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 37 \u0e41\u0e22\u0e01 1-4 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140092\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e42\u0e27\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140092 \u0e1a\u0e08.\u0e42\u0e19\u0e42\u0e27\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 145  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e23\u0e47\u0e04\u0e40\u0e01\u0e47\u0e15\u0e04\u0e25\u0e31\u0e1a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3506 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1749\/9 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140106\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140106 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 3\/74  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 43 \u0e41\u0e22\u0e01 2-1 (\u0e0a\u0e34\u0e19\u0e40\u0e02\u0e15 1\/21) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140114\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e01\u0e34\u0e42\u0e21 \u0e42\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140114 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e01\u0e34\u0e42\u0e21 \u0e42\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 149\/11  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e17\u0e2a\u0e38\u0e02 \u0e16\u0e19\u0e19\u0e40\u0e22\u0e47\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140157\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140157 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/12  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e13\u0e32\u0e2a\u0e34\u0e23\u0e34 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 29 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140173\",\"name_th\":\"\u0e1a\u0e08.915 \u0e25\u0e2d\u0e27\u0e4c\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140173 \u0e1a\u0e08.915 \u0e25\u0e2d\u0e27\u0e4c\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e04\u0e14\u0e35\u0e04\u0e27\u0e32\u0e21 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e41\u0e17\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e35\u0e49\u0e2a\u0e34\u0e19\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 66\/211  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b.87 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140181\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140181 \u0e1a\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19 \u0e44\u0e2a\u0e49\u0e01\u0e23\u0e2d\u0e01 \u0e44\u0e01\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140190\",\"name_th\":\"\u0e1a\u0e08.\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45303\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45303\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140190 \u0e1a\u0e08.\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 45303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 46 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140211\",\"name_th\":\"\u0e1a\u0e08.\u0e13 \u0e1e\u0e25\u0e31\u0e2a \u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140211 \u0e1a\u0e08.\u0e13 \u0e1e\u0e25\u0e31\u0e2a \u0e2a\u0e34\u0e23\u0e34\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07  \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e0a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2b\u0e0d\u0e34\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 778\/93  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140246\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140246 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e49\u0e32\u0e22 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 \u0e1b\u0e49\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1f \u0e1b\u0e49\u0e32\u0e22\u0e2d\u0e04\u0e23\u0e34\u0e25\u0e34\u0e04 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e25\u0e42\u0e01\u0e49 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e30 \u0e1b\u0e49\u0e32\u0e22\u0e44\u0e1f\u0e41\u0e2d\u0e25\u0e2d\u0e35\u0e14\u0e35 (led) \u0e1b\u0e49\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 409  \u0e16\u0e19\u0e19\u0e42\u0e01\u0e2a\u0e38\u0e21\u0e23\u0e27\u0e21\u0e43\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140271\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e27\u0e35\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140271 \u0e1a\u0e08.\u0e08\u0e35\u0e27\u0e35\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 859  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 94 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140289\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e17\u0e39\u0e42\u0e2d\u0e42\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140289 \u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e17\u0e39\u0e42\u0e2d\u0e42\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 16  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e21\u0e19\u0e18\u0e32\u0e15\u0e38\u0e2f \u0e41\u0e22\u0e01 35-13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140319\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e49\u0e07 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140319 \u0e1a\u0e08.\u0e40\u0e21\u0e49\u0e07 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 10751 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 46\/32  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e18\u0e19\u0e27\u0e23\u0e23\u0e13 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 52\u0e41\u0e22\u0e0141 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140335\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e \u0e42\u0e04\u0e25\u0e18 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47511\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47511\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140335 \u0e1a\u0e08.\u0e44\u0e2e \u0e42\u0e04\u0e25\u0e18 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47511 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e31\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19 \u0e1c\u0e49\u0e32\u0e21\u0e49\u0e27\u0e19 \u0e1c\u0e49\u0e32\u0e17\u0e2d \u0e1c\u0e49\u0e32\u0e16\u0e31\u0e01 \u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b  \u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e49\u0e32\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/29  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140360\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e18\u0e34\u0e14\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c(\u0e40\u0e23\u0e34\u0e48\u0e14\u0e40\u0e25\u0e22\u0e41\u0e2b\u0e25\u0e30) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140360 \u0e1a\u0e08.\u0e27\u0e18\u0e34\u0e14\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c(\u0e40\u0e23\u0e34\u0e48\u0e14\u0e40\u0e25\u0e22\u0e41\u0e2b\u0e25\u0e30) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 109\/59  \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e3229 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140378\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140378 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e1b\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e21\u0e32\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e41\u0e02\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e31\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14 \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e2a\u0e30\u0e14\u0e27\u0e01\u0e14\u0e49\u0e32\u0e19\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u4e0d\u52d5\u7523 137\/8  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17103\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140386\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e38\u0e07\u0e01\u0e31\u0e1b\u0e15\u0e31\u0e19-\u0e27\u0e32\u0e01\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140386 \u0e1a\u0e08.\u0e25\u0e38\u0e07\u0e01\u0e31\u0e1b\u0e15\u0e31\u0e19-\u0e27\u0e32\u0e01\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 103\/10  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 26 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140505\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140505 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 81100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 25\/1  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 111 \u0e41\u0e22\u0e014-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140513\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e40\u0e1b\u0e0b \u0e23\u0e39\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140513 \u0e1a\u0e08.\u0e2a\u0e40\u0e1b\u0e0b \u0e23\u0e39\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 199\/22  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140521\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e2a\u0e4c\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140521 \u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e2a\u0e4c\u0e40\u0e0b\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e08\u0e31\u0e01\u0e2a\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e2d\u0e17\u0e2d\u0e1b (otop) \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/239  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e3214 \u0e41\u0e22\u0e013 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140530\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e35\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140530 \u0e1a\u0e08.\u0e40\u0e27\u0e35\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e35\u0e48\u0e21\u0e34\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e49\u0e32\u0e21\u0e44\u0e27\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 474\/54  \u0e16\u0e19\u0e19\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140548\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140548 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e19\u0e31\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 6  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c 3 \u0e41\u0e22\u0e01 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140564\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1e\u0e23\u0e23\u0e13\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140564 \u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1e\u0e23\u0e23\u0e13\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e35\u0e25\u0e21 9 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140572\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140572 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 326  \u0e0b\u0e2d\u0e22 8 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140581\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140581 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/33  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 20\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140602\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49\u0e40\u0e21\u0e14 \u0e25\u0e32\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140602 \u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49\u0e40\u0e21\u0e14 \u0e25\u0e32\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e41\u0e25\u0e47\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u533b\u7642\u30fb\u798f\u7949 15\/11  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 66 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140637\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140637 \u0e1a\u0e08.\u0e19\u0e32\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 193\/7  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140645\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140645 \u0e1a\u0e08.\u0e27\u0e35\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e49\u0e32\u0e21\u0e49\u0e27\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 39 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140653\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e42\u0e04 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140653 \u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e42\u0e04 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e01\u0e49\u0e44\u0e02\u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 1993   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 203 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140661\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140661 \u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e01\u0e23\u0e30\u0e17\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e04\u0e14\u0e35\u0e43\u0e19\u0e28\u0e32\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e28\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e32\u0e23\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e02\u0e2d\u0e07\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e38\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e41\u0e25\u0e30\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07 \u0e1e\u0e34\u0e19\u0e31\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e23\u0e31\u0e2a\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e19\u0e49\u0e01\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e1e\u0e48\u0e07\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e28\u0e32\u0e25 \u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e42\u0e15\u0e15\u0e38\u0e25\u0e32\u0e01\u0e32\u0e23 \u0e1c\u0e39\u0e49\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e44\u0e15\u0e48\u0e2a\u0e27\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 26\/225  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e01\u0e01\u0e27\u0e34\u0e19 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140670\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e08\u0e40\u0e27\u0e35\u0e22\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140670 \u0e1a\u0e08.\u0e42\u0e08\u0e40\u0e27\u0e35\u0e22\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47723 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7\/3  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140696\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d.\u0e40\u0e2d\u0e47\u0e19 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140696 \u0e1a\u0e08.\u0e42\u0e2d.\u0e40\u0e2d\u0e47\u0e19 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 617\/5  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140769\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e2d\u0e32\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140769 \u0e1a\u0e08.\u0e42\u0e19\u0e2d\u0e32\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e0a\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e07\u0e0a\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e41\u0e1f \u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e1a\u0e19\u0e42\u0e15\u0e4a\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 103  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e40\u0e0a\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e31\u0e07 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140807\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e40\u0e21\u0e48 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140807 \u0e1a\u0e08.\u0e42\u0e0b\u0e40\u0e21\u0e48 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u533b\u7642\u30fb\u798f\u7949 1060  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140815\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e21\u0e44\u0e17\u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e25\u0e08\u0e35\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140815 \u0e1a\u0e08.\u0e18\u0e32\u0e21\u0e44\u0e17\u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e25\u0e08\u0e35\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 27\/45  \u0e0b\u0e2d\u0e22 \u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e34 15(\u0e19\u0e32\u0e2a\u0e27\u0e19-\u0e40\u0e19\u0e35\u0e22\u0e21\u0e01\u0e25\u0e48\u0e33) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140866\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140866 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e49\u0e32\u0e27\u0e01\u0e25\u0e48\u0e2d\u0e07  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19  \u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 78\/4  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35\u0e40\u0e1e\u0e25\u0e2a \u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a-\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140882\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140882 \u0e1a\u0e08.\u0e04\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e1b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 299\/165  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140904\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e41\u0e2d\u0e25\u0e08\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140904 \u0e1a\u0e08.\u0e42\u0e2d\u0e41\u0e2d\u0e25\u0e08\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 70101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c111  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1924 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140912\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e30\u0e40\u0e21\u0e0a\u0e34\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140912 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e30\u0e40\u0e21\u0e0a\u0e34\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e15\u0e31\u0e14\u0e1c\u0e21\u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21 \u0e2a\u0e23\u0e30\u0e44\u0e14\u0e1c\u0e21 \u0e2d\u0e1a\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e27\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 58  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2781(\u0e10\u0e34\u0e15\u0e1e\u0e23) \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140955\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140955 \u0e1a\u0e08.\u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 3\/2  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 7 \u0e41\u0e22\u0e014 (\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e32) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140963\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a\u0e42\u0e01\u0e23\u0e19 \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140963 \u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a\u0e42\u0e01\u0e23\u0e19 \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e41\u0e25\u0e47\u0e1b\u0e42\u0e01\u0e23\u0e19(lab grown diamond) \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e0a\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 3\/1  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e32\u0e42\u0e21\u0e17\u0e22\u0e4c 3 \u0e16\u0e19\u0e19\u0e21\u0e40\u0e2b\u0e2a\u0e31\u0e01\u0e02\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140980\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e2d\u0e23\u0e23\u0e31\u0e15\u0e19\u0e01\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140980 \u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e2d\u0e23\u0e23\u0e31\u0e15\u0e19\u0e01\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 90\/432  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 26 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024505\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e2d\u0e23\u0e4c\u0e1a\u0e31\u0e25 \u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c\u0e17\u0e32\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024505 \u0e1a\u0e08.\u0e40\u0e2e\u0e2d\u0e23\u0e4c\u0e1a\u0e31\u0e25 \u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c\u0e17\u0e32\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61\/258  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e2d\u0e38\u0e14\u0e21\u0e40\u0e14\u0e0a \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024513\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e14\u0e4c \u0e0b\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47892\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47892\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024513 \u0e1a\u0e08.\u0e0b\u0e32\u0e27\u0e14\u0e4c \u0e0b\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47892 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e2d\u0e20\u0e32\u0e1e \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/152  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c92 \u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07-\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024521\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e22\u0e39\u0e1e\u0e35\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024521 \u0e1a\u0e08.\u0e40\u0e2d\u0e22\u0e39\u0e1e\u0e35\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 74200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e1e(retouch) \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 363  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024548\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e34\u0e27\u0e1b\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024548 \u0e1a\u0e08.\u0e13\u0e34\u0e27\u0e1b\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25   \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 57\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e15\u0e19\u0e42\u0e0a\u0e04 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024556\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024556 \u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e21\u0e39\u0e2a\u0e14 \u0e0a\u0e19\u0e34\u0e14\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39\u0e2a\u0e14\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e44\u0e01\u0e48\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e44\u0e01\u0e48\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 64\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024564\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35 \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024564 \u0e1a\u0e08.\u0e23\u0e35 \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 26  \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e15\u0e30\u0e40\u0e04\u0e47\u0e14\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024602\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e49\u0e14\u0e0b\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024602 \u0e1a\u0e08.\u0e42\u0e23\u0e49\u0e14\u0e0b\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e31\u0e1a\u0e15\u0e48\u0e2d \u0e1e\u0e23\u0e1a.  \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e21\u0e25\u0e1e\u0e34\u0e29 \u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 50\/315  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024629\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17\u0e40\u0e04\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024629 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17\u0e40\u0e04\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e25\u0e35\u0e19\u0e34\u0e01\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1188\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024661\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e35 59 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024661 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e35 59 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 988\/341  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e25\u0e25\u0e32\u0e08\u0e08\u0e34\u0e42\u0e2d 2 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c-\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024670\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e4c \u0e23\u0e39\u0e17 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024670 \u0e1a\u0e08.\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e4c \u0e23\u0e39\u0e17 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 51\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024700\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e2b\u0e21\u0e39\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11049\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11049\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024700 \u0e1a\u0e08.\u0e01\u0e2d\u0e07\u0e17\u0e31\u0e1e\u0e2b\u0e21\u0e39\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 11049 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u88fd\u9020 89\/155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024726\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e41\u0e2d\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024726 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e41\u0e2d\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 2080\/162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e41\u0e1a\u0e23\u0e34\u0e48\u0e0740\/3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024734\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024734 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 159\/42  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e31\u0e13\u0e11\u0e19\u0e32 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c-\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e32\u0e21\u0e41\u0e14\u0e07-\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027849\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e1f\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027849 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e1f\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e27\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 168\/103  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e31\u0e13\u0e11\u0e19\u0e32 \u0e40\u0e27\u0e2a\u0e15\u0e4c\u0e40\u0e01\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027857\",\"name_th\":\"\u0e1a\u0e08. \u0e1b\u0e4b\u0e32\u0e42\u0e19\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027857 \u0e1a\u0e08. \u0e1b\u0e4b\u0e32\u0e42\u0e19\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 55\/314  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e1e\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027865\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e27\u0e32\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027865 \u0e1a\u0e08.\u0e42\u0e21\u0e27\u0e32\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 247  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c3 \u0e0b\u0e2d\u0e22 13 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027881\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e1a\u0e25\u0e04 \u0e1f\u0e34\u0e15\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027881 \u0e1a\u0e08. \u0e40\u0e1a\u0e25\u0e04 \u0e1f\u0e34\u0e15\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32 \u0e0a\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \/ e-commerce) \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/178  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e31\u0e19\u0e17\u0e27\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027903\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e35 \u0e21\u0e35\u0e1a\u0e38\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47111\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47111\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027903 \u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e35 \u0e21\u0e35\u0e1a\u0e38\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47111 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027920\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e40\u0e15\u0e49\u0e41\u0e25\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027920 \u0e1a\u0e08.\u0e25\u0e32\u0e40\u0e15\u0e49\u0e41\u0e25\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25 \u0e41\u0e25\u0e30 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 78\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027946\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e42\u0e2d\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027946 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e42\u0e2d\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u60c5\u5831\u901a\u4fe1\u30fbit 166\/30  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e073 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027954\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e17\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027954 \u0e1a\u0e08.\u0e2a\u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e17\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2\/37  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e34\u0e15\u0e15\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027989\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1e\u0e25\u0e34\u0e01 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027989 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1e\u0e25\u0e34\u0e01 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 (custom software) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u60c5\u5831\u901a\u4fe1\u30fbit 87\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027997\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e08\u0e35. \u0e2a\u0e01\u0e34\u0e19 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027997 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e08\u0e35. \u0e2a\u0e01\u0e34\u0e19 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07  \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/138  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e21\u0e14\u0e34 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 12 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028004\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028004 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028012\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e21\u0e32\u0e19 \u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028012 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e21\u0e32\u0e19 \u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e40\u0e0a\u0e48\u0e32  \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 69\/236  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028021\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028021 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028039\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028039 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\/\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 244  \u0e16\u0e19\u0e19\u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028047\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e1b\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028047 \u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e1b\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\/\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 333\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028055\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e04 \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028055 \u0e1a\u0e08.\u0e40\u0e17\u0e04 \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 134\/323  \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569028063\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e1b\u0e31\u0e07\u0e1b\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028063 \u0e1a\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e1b\u0e31\u0e07\u0e1b\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 120\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002631\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e15\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002631 \u0e2b\u0e08.\u0e44\u0e15\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 2569-07-24 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200\/5-7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002640\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e32\u0e04\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e31\u0e27\u0e23\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002640 \u0e2b\u0e08.\u0e18\u0e19\u0e32\u0e04\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e31\u0e27\u0e23\u0e4c 2569-07-24 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 27\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022855\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e21\u0e35 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022855 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e21\u0e35 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022863\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e19\u0e34\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022863 \u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e19\u0e34\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 78300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 21\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022880\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e2d\u0e1e\u0e35\u0e1e\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022880 \u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e2d\u0e1e\u0e35\u0e1e\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e23\u0e30\u0e1a\u0e1a \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c(ai) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 2\/517  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e38\u0e23\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 8\/3 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e35\u0e48 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022898\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34\u0e41\u0e2d\u0e14\u0e14\u0e34\u0e04\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022898 \u0e1a\u0e08.\u0e14\u0e34\u0e41\u0e2d\u0e14\u0e14\u0e34\u0e04\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46\u0e14\u0e49\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u82b8\u8853\u30fb\u5a2f\u697d 89\/115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022901\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e49\u0e27\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022901 \u0e1a\u0e08.\u0e2d\u0e49\u0e27\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e0d\u52d5\u7523 46\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022910\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e1f\u0e1a\u0e32\u0e2a \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56299\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56299\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022910 \u0e1a\u0e08.\u0e40\u0e0a\u0e1f\u0e1a\u0e32\u0e2a \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e2d\u0e2a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e0b\u0e2d\u0e2a\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e07 \u0e19\u0e49\u0e33\u0e2a\u0e25\u0e31\u0e14 \u0e19\u0e49\u0e33\u0e2b\u0e21\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 48\/408  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022936\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e0a\u0e34 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022936 \u0e1a\u0e08.\u0e21\u0e32\u0e0a\u0e34 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e49\u0e33\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1f\u0e23 \u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e32\u0e19\u0e40\u0e25\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u88fd\u9020 2\/712  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e38\u0e23\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022961\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e04\u0e23\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29302\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29302\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022961 \u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e04\u0e23\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 29302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u88fd\u9020 27\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022979\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e21\u0e43\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022979 \u0e1a\u0e08.\u0e25\u0e21\u0e43\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022987\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e40\u0e1b\u0e48\u0e32 \u0e21\u0e34\u0e19\u0e34\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022987 \u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e40\u0e1b\u0e48\u0e32 \u0e21\u0e34\u0e19\u0e34\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022995\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022995 \u0e1a\u0e08.\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e33 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e2a\u0e2d\u0e19 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e01\u0e43\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u6559\u80b2 36  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023002\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e13\u0e20\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023002 \u0e1a\u0e08.\u0e23\u0e13\u0e20\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 88\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023011\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e37\u0e2d\u0e42\u0e2b\u0e22 \u0e17\u0e48\u0e32\u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023011 \u0e1a\u0e08.\u0e40\u0e2a\u0e37\u0e2d\u0e42\u0e2b\u0e22 \u0e17\u0e48\u0e32\u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21 \u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07 \u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 50\/157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023029\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e31\u0e07 \u0e44\u0e14\u0e19\u0e32\u0e2a\u0e15\u0e35\u0e49 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023029 \u0e1a\u0e08.\u0e16\u0e31\u0e07 \u0e44\u0e14\u0e19\u0e32\u0e2a\u0e15\u0e35\u0e49 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023037\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e28\u0e23\u0e28\u0e10\u0e4c\u0e0a\u0e27\u0e34\u0e28 \u0e44\u0e1e\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023037 \u0e1a\u0e08.\u0e40\u0e28\u0e23\u0e28\u0e10\u0e4c\u0e0a\u0e27\u0e34\u0e28 \u0e44\u0e1e\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43901 \u0e17\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e31\u0e1a\u0e40\u0e08\u0e32\u0e30\u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21  \u0e15\u0e2d\u0e01\u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21 \u5efa\u8a2d 65\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023045\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e19\u0e40\u0e17\u0e34\u0e25 \u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023045 \u0e1a\u0e08.\u0e40\u0e08\u0e19\u0e40\u0e17\u0e34\u0e25 \u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e49\u0e33\u0e22\u0e32\u0e40\u0e04\u0e21\u0e35  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e19\u0e49\u0e33\u0e22\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14  \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46  \u0e40\u0e0a\u0e48\u0e19  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e41\u0e25\u0e30\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u88fd\u9020 132\/246  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023053\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e41\u0e04\u0e23\u0e4c \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023053 \u0e1a\u0e08.\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e41\u0e04\u0e23\u0e4c \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 3\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023061\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"30110\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"30110\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023061 \u0e1a\u0e08.\u0e18\u0e19\u0e0a\u0e32\u0e15 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 30110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e48\u0e19\u0e25\u0e2d\u0e22\u0e19\u0e49\u0e33 \u0e41\u0e1e\u0e25\u0e2d\u0e22\u0e19\u0e49\u0e33 \u0e1a\u0e49\u0e32\u0e19\u0e25\u0e2d\u0e22\u0e19\u0e49\u0e33 \u0e41\u0e1e\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e48\u0e19\u0e19\u0e49\u0e33\u0e1e\u0e38\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u88fd\u9020 95\/452  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023070\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0b\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023070 \u0e1a\u0e08.\u0e44\u0e0b\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 96309 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19  \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23  \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23  \u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 40\/03103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023096\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e32\u0e25\u0e34\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023096 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e32\u0e25\u0e34\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 36\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004849\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e30 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004849 \u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e30 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004857\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e20\u0e32\u0e1e\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004857 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e20\u0e32\u0e1e\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004865\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e01\u0e39\u0e23\u0e4c\u0e40\u0e21\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004865 \u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e01\u0e39\u0e23\u0e4c\u0e40\u0e21\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23\/\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 52\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004873\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e32\u0e14\u0e35\u0e49\u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004873 \u0e1a\u0e08.\u0e40\u0e1f\u0e32\u0e14\u0e35\u0e49\u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004890\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e40\u0e1f\u0e23\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004890 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e40\u0e1f\u0e23\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 186  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0163569000582\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e1e\u0e39\u0e19\u0e41\u0e01\u0e49\u0e27\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000582 \u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e1e\u0e39\u0e19\u0e41\u0e01\u0e49\u0e27 2569-07-24 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001742\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23369 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001742 \u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23369 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e2d\u0e49\u0e2d\u0e22 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0183569000299\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0183569000299 \u0e2b\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 2569-07-24 1000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e16\u0e21\u0e14\u0e34\u0e19 \u0e02\u0e38\u0e14\u0e04\u0e25\u0e2d\u0e07 \u0e25\u0e2d\u0e01\u0e04\u0e25\u0e2d\u0e07 \u5efa\u8a2d 143  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e41\u0e02\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0195569002684\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002684 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e22\u0e32\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d-\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 112\/9  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e253 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0202569000050\",\"name_th\":\"\u0e2b\u0e2a.\u0e1e\u0e35.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e21. \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0202569000050 \u0e2b\u0e2a.\u0e1e\u0e35.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e21. \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-24 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 39\/250  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003254\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e20\u0e13\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003254 \u0e2b\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e20\u0e13\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2569-07-24 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 105\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 19 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038815\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e12\u0e19\u0e4c\u0e40\u0e25\u0e34\u0e28\u0e22\u0e28 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038815 \u0e1a\u0e08.\u0e1e\u0e31\u0e12\u0e19\u0e4c\u0e40\u0e25\u0e34\u0e28\u0e22\u0e28 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 97\/17  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e20\u0e34\u0e0a\u0e22\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038840\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038840 \u0e1a\u0e08.\u0e18\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e14\u0e2a\u0e35\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e07\u0e32  \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e31\u0e14\u0e40\u0e07\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e1a\u0e23\u0e01 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e04\u0e25\u0e31\u0e0a\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e1a\u0e32\u0e30 \u0e1e\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e1a\u0e32\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038858\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038858 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e33\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038891\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038891 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138\/166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038912\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e3527 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038912 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e3527 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 369\/59  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e23\u0e34\u0e28\u0e32 (\u0e40\u0e14\u0e2d\u0e30\u0e44\u0e1f\u0e19\u0e4c\u0e40\u0e19\u0e2a\u0e17\u0e32\u0e27\u0e19\u0e4c) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038939\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e1b\u0e23  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038939 \u0e1a\u0e08.\u0e23\u0e34\u0e0a \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e1b\u0e23  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038963\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e1a\u0e0a\u0e32\u0e07\u0e2d\u0e31\u0e19 \u0e23\u0e2a\u0e08\u0e35\u0e19\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038963 \u0e1a\u0e08.\u0e1e\u0e1a\u0e0a\u0e32\u0e07\u0e2d\u0e31\u0e19 \u0e23\u0e2a\u0e08\u0e35\u0e19\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e35\u0e19 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e31\u0e48\u0e07\u0e23\u0e31\u0e1a \u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 (delivery) \u5bbf\u6cca\u30fb\u98f2\u98df 99\/98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038971\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e25\u0e32\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038971 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e25\u0e32\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138\/117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038998\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038998 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 114\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009823\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e21\u0e32-\u0e0a\u0e34\u0e25 888  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009823 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e21\u0e32-\u0e0a\u0e34\u0e25 888  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 120\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009858\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e1a\u0e38\u0e0d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009858 \u0e1a\u0e08.\u0e21\u0e35\u0e1a\u0e38\u0e0d \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46109 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/258  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009882\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e04\u0e2d\u0e19\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009882 \u0e1a\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e04\u0e2d\u0e19\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46699 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e19\u0e49\u0e33\u0e22\u0e32\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e07\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009891\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009891 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e22\u0e48\u0e2d\u0e22\u0e02\u0e19\u0e32\u0e14 \u0e2d\u0e31\u0e14\u0e01\u0e49\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e0b\u0e36\u0e48\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 \u0e02\u0e22\u0e30\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 658  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009904\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e01\u0e25\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86902\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86902\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009904 \u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e01\u0e25\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 86902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u533b\u7642\u30fb\u798f\u7949 40\/1  \u0e0b\u0e2d\u0e22 \u0e2b\u0e19\u0e2d\u0e07\u0e41\u0e15\u0e07\u0e42\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569004015\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004015 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 13\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569004040\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004040 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u904b\u8f38\u30fb\u7269\u6d41 1\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002144\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e25 \u0e40\u0e2d \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002144 \u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e25 \u0e40\u0e2d \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e40\u0e14\u0e34\u0e19\u0e17\u0e48\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u5efa\u8a2d 133\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002931\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e23\u0e0b\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e41\u0e04\u0e23\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002931 \u0e2b\u0e08.\u0e40\u0e01\u0e23\u0e0b\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e41\u0e04\u0e23\u0e4c 2569-07-24 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002940\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002940 \u0e2b\u0e08.\u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 2569-07-24 1000000 11041 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e1a\u0e1a\u0e41\u0e1e\u0e47\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 198\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007650\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e42\u0e2d\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007650 \u0e1a\u0e08.\u0e44\u0e1e\u0e42\u0e2d\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 456\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001137\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001137 \u0e2b\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-24 1000000 42101 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 69  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e1c\u0e48\u0e19\u0e49\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0313569001145\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e34\u0e23\u0e38\u0e15\u0e15\u0e4c \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001145 \u0e2b\u0e08.\u0e19\u0e34\u0e23\u0e38\u0e15\u0e15\u0e4c \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-24 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569002011\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19\u0e34\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569002011 \u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19\u0e34\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 134  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569002020\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e22\u0e32\u0e25\u0e30\u0e2b\u0e32\u0e19\u0e17\u0e23\u0e32\u0e22 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569002020 \u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e22\u0e32\u0e25\u0e30\u0e2b\u0e32\u0e19\u0e17\u0e23\u0e32\u0e22 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47721 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e17\u0e33\u0e22\u0e32\u0e44\u0e17\u0e22\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0323569000581\",\"name_th\":\"\u0e2b\u0e08.\u0e10\u0e20\u0e31\u0e17\u0e23\u0e4c\u0e0a\u0e19\u0e01\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000581 \u0e2b\u0e08.\u0e10\u0e20\u0e31\u0e17\u0e23\u0e4c\u0e0a\u0e19\u0e01 2569-07-24 1000000 47190 \u0e1b\u0e23\u0e30\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 404,404\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0325569001279\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e2a\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e02\u0e32\u0e22\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001279 \u0e1a\u0e08.\u0e23\u0e31\u0e2a\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e02\u0e32\u0e22\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 291  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0325569001287\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001287 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 3\/42  \u0e16\u0e19\u0e19\u0e28\u0e34\u0e23\u0e34\u0e23\u0e31\u0e10 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0333569000718\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d \u0e40\u0e08 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000718 \u0e2b\u0e08.\u0e40\u0e2d \u0e40\u0e08 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a 2569-07-24 1000000 93111 \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 282\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0335569001171\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001171 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 158  \u0e16\u0e19\u0e19\u0e02\u0e38\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569002010\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e49\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c19\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569002010 \u0e2b\u0e08.\u0e01\u0e49\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c19 2569-07-24 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 88\/104  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 the river ubon \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003395\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003395 \u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/123  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e32\u0e23\u0e34\u0e19\u0e27\u0e34\u0e2a\u0e15\u0e49\u0e32\u0e2a\u0e27\u0e19\u0e27\u0e19\u0e32\u0e23\u0e21\u0e22\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0393569000378\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e34\u0e15 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000378 \u0e2b\u0e08.\u0e21\u0e34\u0e15 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 2569-07-24 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e17\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0393569000386\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000386 \u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c 2569-07-24 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0403569003309\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e48\u0e19\u0e42\u0e2e\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003309 \u0e2b\u0e08.\u0e41\u0e01\u0e48\u0e19\u0e42\u0e2e\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-24 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e2b\u0e23\u0e32\u0e0a\u0e40\u0e14\u0e42\u0e0a\u0e44\u0e0a\u0e22 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007152\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007152 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 78300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007161\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e38\u0e07\u0e1e\u0e25\u0e38\u0e49\u0e22 \u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007161 \u0e1a\u0e08.\u0e1e\u0e38\u0e07\u0e1e\u0e25\u0e38\u0e49\u0e22 \u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 164  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007187\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19 \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007187 \u0e1a\u0e08.\u0e18\u0e19 \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e01\u0e47\u0e2a \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 258  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007195\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e32\u0e01\u0e23\u0e32\u0e1f 41 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007195 \u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e32\u0e01\u0e23\u0e32\u0e1f 41 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 69200 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23  \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 490  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007225\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007225 \u0e1a\u0e08.\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d \u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43223 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5efa\u8a2d 456  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001721\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e44\u0e2d \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001721 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e44\u0e2d \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 2569-07-24 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e14\u0e39\u0e41\u0e25 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1f\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 253\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003947\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003947 \u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 819  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003971\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e2d\u0e25\u0e39\u0e42\u0e2e\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003971 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e2d\u0e25\u0e39\u0e42\u0e2e\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e07\u0e32\u0e19\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e41\u0e19\u0e07\u0e07\u0e32\u0e19\u0e21\u0e38\u0e49\u0e07\u0e08\u0e35\u0e1a \u0e21\u0e38\u0e49\u0e07\u0e25\u0e27\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 321\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e04\u0e33\u0e1a\u0e07 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003980\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003980 \u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e2a\u0e35\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 298  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0453569001098\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e39\u0e48\u0e2a\u0e38\u0e23\u0e31\u0e15\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001098 \u0e2b\u0e08.\u0e2d\u0e39\u0e48\u0e2a\u0e38\u0e23\u0e31\u0e15\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 2569-07-24 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16 \u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e40\u0e1a\u0e23\u0e04 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0453569001101\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e31\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1b\u0e49\u0e07\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001101 \u0e2b\u0e08.\u0e1b\u0e31\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e1b\u0e49\u0e07 2569-07-24 1000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u88fd\u9020 72  \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e19\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e04\u0e34\u0e14 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001545\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e4b\u0e2d\u0e07\u0e41\u0e1b\u0e4b\u0e07 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e2a\u0e15\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001545 \u0e1a\u0e08.\u0e1b\u0e4b\u0e2d\u0e07\u0e41\u0e1b\u0e4b\u0e07 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e2a\u0e15\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 74109 \u0e15\u0e31\u0e14\u0e0a\u0e38\u0e14 \u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e1e\u0e17\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e2a\u0e23\u0e35\u0e23\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0503569005190\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e21\u0e21\u0e42\u0e21\u0e21\u0e34\u0e25\u0e04\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005190 \u0e2b\u0e08.\u0e40\u0e21\u0e21\u0e42\u0e21\u0e21\u0e34\u0e25\u0e04\u0e4c 2569-07-24 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e19\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e21\u0e22\u0e39\u0e40\u0e2d\u0e0a\u0e17\u0e35 \u0e19\u0e21\u0e1e\u0e32\u0e2a\u0e40\u0e08\u0e2d\u0e44\u0e23\u0e0b\u0e4c \u0e19\u0e21\u0e40\u0e1b\u0e23\u0e35\u0e49\u0e22\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e40\u0e17\u0e1e \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569005203\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e19\u0e40\u0e04.\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005203 \u0e2b\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e19\u0e40\u0e04.\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 2569-07-24 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 121\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569005211\",\"name_th\":\"\u0e2b\u0e08.\u0e16\u0e27\u0e34\u0e25 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005211 \u0e2b\u0e08.\u0e16\u0e27\u0e34\u0e25 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-24 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 171  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016649\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e21\u0e32\u0e23\u0e4c\u0e17990 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016649 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e21\u0e32\u0e23\u0e4c\u0e17990 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e1d\u0e32\u0e01 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 193  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016673\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e35\u0e21\u0e35\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016673 \u0e1a\u0e08.\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e35\u0e21\u0e35\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07  \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u88fd\u9020 28\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016690\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e44\u0e01\u0e48\u0e2a\u0e32\u0e22\u0e2a\u0e30\u0e40\u0e21\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016690 \u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e44\u0e01\u0e48\u0e2a\u0e32\u0e22\u0e2a\u0e30\u0e40\u0e21\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 58\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016703\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55901\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55901\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016703 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 55901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e1a\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e1b\u0e35 \u5bbf\u6cca\u30fb\u98f2\u98df 88\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016711\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e13\u0e13\u0e4c\u0e08\u0e34\u0e19\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016711 \u0e1a\u0e08.\u0e08\u0e34\u0e13\u0e13\u0e4c\u0e08\u0e34\u0e19\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000791\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 92\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000791 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 92 2569-07-24 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e01\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 158  \u0e16\u0e19\u0e19\u0e23\u0e2d\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0513569000805\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000805 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08 2569-07-24 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e07\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e07\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001445\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 999\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001445 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 999 2569-07-24 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0543569000309\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0543569000309 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f 2569-07-24 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c (event organizer) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0553569000449\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e25 (\u0e19\u0e48\u0e32\u0e19)\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0553569000449 \u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e25 (\u0e19\u0e48\u0e32\u0e19) 2569-07-24 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 19\/1  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e32\u0e22\u0e28 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0563569000643\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e2d\u0e25\u0e25\u0e4c\u0e44\u0e25\u0e1f\u0e4c \u0e23\u0e35\u0e40\u0e17\u0e25\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0563569000643 \u0e2b\u0e08.\u0e2d\u0e2d\u0e25\u0e25\u0e4c\u0e44\u0e25\u0e1f\u0e4c \u0e23\u0e35\u0e40\u0e17\u0e25 2569-07-24 1000000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 354  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0565569000661\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e17\u0e15\u0e35\u0e49 \u0e40\u0e2d\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000661 \u0e1a\u0e08.\u0e41\u0e1e\u0e17\u0e15\u0e35\u0e49 \u0e40\u0e2d\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 388  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0565569000670\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e42\u0e21\u0e14 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000670 \u0e1a\u0e08.\u0e25\u0e32\u0e42\u0e21\u0e14 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e2a\u0e15\u0e23\u0e35 \u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01\u0e2d\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e27\u0e31\u0e15\u0e16\u0e38\u0e43\u0e0a\u0e49\u0e41\u0e17\u0e19 \u0e2b\u0e19\u0e31\u0e07 \u0e22\u0e32\u0e07 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e31\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e2a\u0e49\u0e19\u0e2a\u0e39\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0575569004837\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e19\u0e33\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004837 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e19\u0e33\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e15\u0e34\u0e14\u0e09\u0e25\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u88fd\u9020 33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001738\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001738 \u0e2b\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-24 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001746\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e19\u0e30\u0e21\u0e35\u0e21\u0e32\u0e01\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001746 \u0e2b\u0e08.\u0e21\u0e32\u0e19\u0e30\u0e21\u0e35\u0e21\u0e32\u0e01 2569-07-24 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001754\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e19\u0e34\u0e14\u0e32\u0e40\u0e0b\u0e2d\u0e27\u0e35\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001754 \u0e2b\u0e08.\u0e1e\u0e19\u0e34\u0e14\u0e32\u0e40\u0e0b\u0e2d\u0e27\u0e35 2569-07-24 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002191\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e0b\u0e35 \u0e40\u0e08\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002191 \u0e1a\u0e08.\u0e27\u0e35\u0e0b\u0e35 \u0e40\u0e08\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e22\u0e48\u0e2d\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 14\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0655569002396\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e42\u0e2e\u0e211819\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002396 \u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e42\u0e2e\u0e211819\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 16220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0663569000588\",\"name_th\":\"\u0e2b\u0e08.\u0e10\u0e32\u0e19\u0e17\u0e27\u0e35 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0663569000588 \u0e2b\u0e08.\u0e10\u0e32\u0e19\u0e17\u0e27\u0e35 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-24 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0675569001594\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001594 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e2d\u0e34\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 272  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003359\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e21\u0e2a\u0e34\u0e23\u0e34 \u0e41\u0e2d\u0e2a\u0e41\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003359 \u0e1a\u0e08.\u0e40\u0e01\u0e29\u0e21\u0e2a\u0e34\u0e23\u0e34 \u0e41\u0e2d\u0e2a\u0e41\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003375\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003375 \u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 7\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003391\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e0b\u0e14 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003391 \u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e0b\u0e14 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002786\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e2a\u0e15\u0e32\u0e23\u0e4c 789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002786 \u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e2a\u0e15\u0e32\u0e23\u0e4c 789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e16\u0e38\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002794\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d \u0e40\u0e08\u0e49\u0e32 789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002794 \u0e1a\u0e08.\u0e2d\u0e2d \u0e40\u0e08\u0e49\u0e32 789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e16\u0e38\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002808\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e27\u0e34\u0e28\u0e13\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002808 \u0e1a\u0e08.\u0e1e\u0e23\u0e27\u0e34\u0e28\u0e13\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u88fd\u9020 9\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002204\",\"name_th\":\"\u0e1a\u0e08. \u0e18\u0e27\u0e31\u0e0a\u0e2d\u0e34\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e47\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47999\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47999\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002204 \u0e1a\u0e08. \u0e18\u0e27\u0e31\u0e0a\u0e2d\u0e34\u0e07\u0e04\u0e4c\u0e40\u0e08\u0e47\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007486\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e25\u0e31\u0e01\u0e0b\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007486 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e25\u0e31\u0e01\u0e0b\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43301 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 (interior fit-out) \u5efa\u8a2d 54\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007494\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e2d\u0e21\u0e1e\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49332\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49332\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007494 \u0e1a\u0e08.\u0e08\u0e2d\u0e21\u0e1e\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 49332 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e1e\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27 \u0e19\u0e49\u0e33 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007532\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e19\u0e32\u0e30 \u0e40\u0e27\u0e25\u0e25\u0e4c\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007532 \u0e1a\u0e08.\u0e40\u0e2a\u0e19\u0e32\u0e30 \u0e40\u0e27\u0e25\u0e25\u0e4c\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1c\u0e39\u0e1b\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e1b\u0e48\u0e27\u0e22\u0e23\u0e30\u0e22\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33 (nursing home) \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e44\u0e1b-\u0e01\u0e25\u0e31\u0e1a (day care) \u533b\u7642\u30fb\u798f\u7949 47\/996  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0743569001044\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e02\u0e48\u0e2b\u0e27\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e0b\u0e39\u0e0a\u0e34 \u0e21\u0e2b\u0e32\u0e0a\u0e31\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569001044 \u0e2b\u0e08.\u0e44\u0e02\u0e48\u0e2b\u0e27\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e0b\u0e39\u0e0a\u0e34 \u0e21\u0e2b\u0e32\u0e0a\u0e31\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48 2569-07-24 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e0b\u0e39\u0e0a\u0e34 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e38\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u88fd\u9020 23\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007907\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23103\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23103\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007907 \u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e17\u0e47\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 23103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e16\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e49\u0e33 pe \u0e41\u0e25\u0e30 \u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e01\u0e25\u0e32\u0e2a \u88fd\u9020 9\/321  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007915\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e2a.\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007915 \u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e2a.\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 80\/5-6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007931\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10414\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10414\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007931 \u0e1a\u0e08.\u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 10414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e2d\u0e48\u0e2d\u0e19 \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e41\u0e01\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 75\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007940\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007940 \u0e1a\u0e08.\u0e2d\u0e38\u0e48\u0e19\u0e43\u0e08 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 180\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0763569000340\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e23\u0e1e\u0e44\u0e17\u0e25\u0e4c\u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0763569000340 \u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e23\u0e1e\u0e44\u0e17\u0e25\u0e4c\u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 2569-07-24 1000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 281  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569003103\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003103 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 6\/19  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e31\u0e27\u0e19\u0e32 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 112 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0775569003120\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e22\u0e41\u0e25\u0e30\u0e14\u0e35\u0e21\u0e35\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003120 \u0e1a\u0e08.\u0e2a\u0e27\u0e22\u0e41\u0e25\u0e30\u0e14\u0e35\u0e21\u0e35\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e04\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u533b\u7642\u30fb\u798f\u7949 11\/192  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0775569003138\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35\u0e1e\u0e35-\u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003138 \u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35\u0e1e\u0e35-\u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e1c\u0e48\u0e19\u0e04\u0e2d\u0e21\u0e42\u0e1e\u0e2a\u0e34\u0e17 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e1c\u0e48\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22  \u0e41\u0e1c\u0e48\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e1c\u0e48\u0e19\u0e2d\u0e30\u0e04\u0e23\u0e34\u0e25\u0e34\u0e04 \u0e41\u0e1c\u0e48\u0e19\u0e1e\u0e35\u0e27\u0e35\u0e0b\u0e35 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 378  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002882\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19\u0e34\u0e04\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22 145  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002882 \u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19\u0e34\u0e04\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22 145  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38\u0e44\u0e21\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38\u0e1e\u0e37\u0e0a \u0e15\u0e49\u0e19\u0e01\u0e25\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e1b\u0e38\u0e4b\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013680\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e0a\u0e34\u0e19\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013680 \u0e1a\u0e08.\u0e42\u0e0a\u0e0a\u0e34\u0e19\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f  \u0e04\u0e32\u0e41\u0e1f\u0e48 \u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e0a\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 (delivery) \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u88fd\u9020 74\/28  \u0e16\u0e19\u0e19\u0e1e\u0e39\u0e19\u0e1c\u0e25 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013701\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e07\u0e2a\u0e34\u0e1b\u0e34\u0e22\u0e30\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013701 \u0e1a\u0e08.\u0e14\u0e31\u0e07\u0e2a\u0e34\u0e1b\u0e34\u0e22\u0e30\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e02\u0e19\u0e21\u0e2a\u0e14 \u0e02\u0e19\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 78\/37  \u0e2d\u0e32\u0e04\u0e32\u0e23(\u0e2b\u0e49\u0e32\u0e07\u0e1a\u0e34\u0e4a\u0e01\u0e0b\u0e35 \u0e01\u0e21\u0e25\u0e32)  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 106\/1 ( \u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e2d\u0e40\u0e21\u0e0b\u0e2d\u0e19 ) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e01\u0e21\u0e25\u0e32-\u0e1b\u0e48\u0e32\u0e15\u0e2d\u0e07 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013752\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e02 \u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013752 \u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e02 \u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e48\u0e15\u0e4c\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 132\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013779\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e31\u0e12\u0e15\u0e23\u0e32 \u0e44\u0e25\u0e1f\u0e4c 1992 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013779 \u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e31\u0e12\u0e15\u0e23\u0e32 \u0e44\u0e25\u0e1f\u0e4c 1992 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e1f\u0e2a\u0e1a\u0e38\u0e4a\u0e04 (facebook) \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 116\/156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013787\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013787 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 136\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010842\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e39\u0e25 \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81292\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81292\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010842 \u0e1a\u0e08.\u0e1e\u0e39\u0e25 \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 81292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 72\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010869\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e2b\u0e25\u0e07\u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010869 \u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e2b\u0e25\u0e07\u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e44\u0e21\u0e49\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e2d\u0e31\u0e14\u0e19\u0e4d\u0e49\u0e32\u0e22\u0e32 \u0e41\u0e25\u0e30 \u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u88fd\u9020 196\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0865569001304\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e2d\u0e22 \u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001304 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e2d\u0e22 \u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e17\u0e38\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569006194\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006194 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e34\u0e0a \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 59\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006208\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21 (1448) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006208 \u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21 (1448) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 46202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e15\u0e49\u0e19\u0e01\u0e25\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001125\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e1b\u0e39\u0e0b\u0e35\u0e19 \u0e40\u0e1f\u0e23\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001125 \u0e1a\u0e08.\u0e04\u0e32\u0e1b\u0e39\u0e0b\u0e35\u0e19 \u0e40\u0e1f\u0e23\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110\/4  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e29\u0e0e\u0e32 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0925569001133\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001133 \u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 162\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0945569000773\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e38\u0e48\u0e07 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000773 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e38\u0e48\u0e07 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 1000000 45102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e23\u0e22\u0e2b\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e02\u0e22\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e49\u0e21\u0e1b\u0e31\u0e49\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e17\u0e48\u0e19\u0e2d\u0e31\u0e14\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e19\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19 \u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07\u0e15\u0e35\u0e19\u0e41\u0e01\u0e30 \u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e2b\u0e32\u0e1a\u0e2b\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e1a\u0e1a \u0e2a\u0e30\u0e1e\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e21\u0e04\u0e04\u0e32\u0e19\u0e34\u0e04 (\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e44\u0e01 \u0e2a\u0e48\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e01\u0e25\u0e32\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/6  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e02 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0103569007935\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e23\u0e2a\u0e32 2534 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007935 \u0e2b\u0e08.\u0e2d\u0e23\u0e2a\u0e32 2534 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-23 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 93\/39  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2787(\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007978\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e32\u0e23\u0e4c \u0e41\u0e04\u0e23\u0e4c\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007978 \u0e2b\u0e08.\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e32\u0e23\u0e4c \u0e41\u0e04\u0e23\u0e4c 2569-07-23 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07 \u0e2d\u0e31\u0e14 \u0e09\u0e35\u0e14 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 301\/854  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0768 (\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007986\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e31\u0e19\u0e08\u0e3414\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007986 \u0e2b\u0e08.\u0e0b\u0e31\u0e19\u0e08\u0e3414 2569-07-23 1000000 47113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e21\u0e34\u0e19\u0e34\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 265  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 68 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569008001\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 1995 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008001 \u0e2b\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 1995 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-23 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 174  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 51 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138497\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138497 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 97\/10  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e32\u0e2e\u0e2d\u0e01\u0e01\u0e32\u0e19\u0e35  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1724 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138501\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e0a\u0e0c\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c\u0e41\u0e17\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138501 \u0e1a\u0e08.\u0e21\u0e31\u0e0a\u0e0c\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c\u0e41\u0e17\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25\/308  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 124 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138519\",\"name_th\":\"\u0e1a\u0e08.23 \u0e41\u0e2d\u0e25\u0e44\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138519 \u0e1a\u0e08.23 \u0e41\u0e2d\u0e25\u0e44\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e42\u0e23\u0e04\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e2a\u0e32\u0e02\u0e32\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19) \u533b\u7642\u30fb\u798f\u7949 99\/9  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138543\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e17\u0e39\u0e40\u0e01\u0e47\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138543 \u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e17\u0e39\u0e40\u0e01\u0e47\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1e\u0e23\u0e21 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138551\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e2a\u0e15\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138551 \u0e1a\u0e08.\u0e42\u0e17\u0e2a\u0e15\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 77210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 46\/6  \u0e0b\u0e2d\u0e22 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c4 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138560\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e19\u0e22\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138560 \u0e1a\u0e08.\u0e41\u0e1e\u0e19\u0e22\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 62023 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e2a\u0e32\u0e02\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02 \u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 206\/71  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138578\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e2a\u0e44\u0e25\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138578 \u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e2a\u0e44\u0e25\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e25\u0e32\u0e01\u0e08\u0e39\u0e07 \u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 12\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1b\u0e23\u0e21\u0e2a\u0e34\u0e23\u0e34 \u0e15\u0e36\u0e01\u0e0b\u0e35 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138586\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e27\u0e34\u0e2a\u0e14\u0e49\u0e32 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e17\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138586 \u0e1a\u0e08.\u0e14\u0e35\u0e27\u0e34\u0e2a\u0e14\u0e49\u0e32 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e17\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e2d\u0e1a\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e14\u0e07\u0e20\u0e32\u0e1e \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e19\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e16 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\/\u0e23\u0e16\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\/\u0e23\u0e16\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e20\u0e32\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\/\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19 \u0e22\u0e19\u0e15\u0e4c\/\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23\/\u0e0b\u0e2d\u0e23\u0e4c\u0e1f\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e14\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 314\/11  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e37\u0e2d\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138608\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138608 \u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2b\u0e39\u0e1f\u0e31\u0e07 \u0e2b\u0e39\u0e1f\u0e31\u0e07\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 (bluetooth) \u0e25\u0e33\u0e42\u0e1e\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 206\/44  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138616\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39 \u0e41\u0e2e\u0e14 \u0e21\u0e35 \u0e41\u0e2d\u0e17 \u0e27\u0e39\u0e1f \u0e27\u0e39\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138616 \u0e1a\u0e08.\u0e22\u0e39 \u0e41\u0e2e\u0e14 \u0e21\u0e35 \u0e41\u0e2d\u0e17 \u0e27\u0e39\u0e1f \u0e27\u0e39\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e15\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 236\/69  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 68 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138641\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e1e\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138641 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e1e\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/75  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138659\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e40\u0e1a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138659 \u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e40\u0e1a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e1b\u0e49\u0e07\u0e17\u0e33\u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e2a\u0e21\u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e33\u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 118 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138667\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e25\u0e40\u0e15\u0e19\u0e32\u0e15\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138667 \u0e1a\u0e08.\u0e42\u0e25\u0e40\u0e15\u0e19\u0e32\u0e15\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 - \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 86 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138675\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e0b\u0e38 \u0e2d\u0e34\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138675 \u0e1a\u0e08.\u0e2e\u0e32\u0e0b\u0e38 \u0e2d\u0e34\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47732 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149  \u0e16\u0e19\u0e19\u0e40\u0e22\u0e32\u0e27\u0e1e\u0e32\u0e13\u0e34\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138683\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e19\u0e14\u0e30 \u0e42\u0e14\u0e1a\u0e38\u0e17\u0e0b\u0e36 \u0e0a\u0e34\u0e40\u0e23\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10802\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10802\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138683 \u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e19\u0e14\u0e30 \u0e42\u0e14\u0e1a\u0e38\u0e17\u0e0b\u0e36 \u0e0a\u0e34\u0e40\u0e23\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 10802 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 1\/152  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 101 \u0e0b\u0e2d\u0e22 53 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138691\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e25\u0e39\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138691 \u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e25\u0e39\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e35.\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3504 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138705\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e2d\u0e40\u0e15\u0e48\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138705 \u0e1a\u0e08.\u0e15\u0e2d\u0e40\u0e15\u0e48\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46522 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71\/2  \u0e0b\u0e2d\u0e22 \u0e1e\u0e36\u0e48\u0e07\u0e21\u0e35 29 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138713\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e42\u0e14\u0e27\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138713 \u0e1a\u0e08.\u0e40\u0e21\u0e42\u0e14\u0e27\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u4e0d\u52d5\u7523 95\/167  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e40\u0e1e\u0e25\u0e2a \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9-\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c-\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138772\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e04 \u0e17\u0e39 \u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138772 \u0e1a\u0e08.\u0e41\u0e1a\u0e04 \u0e17\u0e39 \u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19 \u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e40\u0e0a\u0e48\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e42\u0e1b\u0e23\u0e42\u0e21\u0e17 \u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 98  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138799\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e43\u0e08 \u0e44\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47221\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47221\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138799 \u0e1a\u0e08.\u0e2a\u0e21\u0e43\u0e08 \u0e44\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/116  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e23\u0e32\u0e23\u0e21\u0e22\u0e4c 69 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1d\u0e31\u0e48\u0e07\u0e43\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138829\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c  \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138829 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c  \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e16\u0e21\u0e14\u0e34\u0e19 \u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5efa\u8a2d 21  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138845\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e35\u0e41\u0e2d\u0e25 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138845 \u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e35\u0e41\u0e2d\u0e25 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 344  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e40\u0e02\u0e19 3 \u0e0b\u0e2d\u0e22 8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138896\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e19\u0e34\u0e27\u0e17\u0e23\u0e32 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138896 \u0e1a\u0e08.\u0e44\u0e2d\u0e19\u0e34\u0e27\u0e17\u0e23\u0e32 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e22\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e38\u0e07\u0e22\u0e32\u0e15\u0e32\u0e21\u0e43\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e41\u0e1e\u0e17\u0e22\u0e4c \u88fd\u9020 363  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 107 (\u0e14\u0e35\u0e2a\u0e21\u0e42\u0e0a\u0e04) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138900\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e01\u0e23\u0e35\u0e19  \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74902\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74902\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138900 \u0e1a\u0e08.\u0e23\u0e35\u0e01\u0e23\u0e35\u0e19  \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 74902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c iot \u0e41\u0e25\u0e30 ai \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21  \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e2b\u0e25\u0e31\u0e01 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e25\u0e14\u0e01\u0e4a\u0e32\u0e0b\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01 (mitigation) \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e20\u0e32\u0e27\u0e30\u0e01\u0e4a\u0e32\u0e0b\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01(adaptation) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 96\/1  \u0e16\u0e19\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138918\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e19\u0e2a\u0e38\u0e02 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138918 \u0e1a\u0e08.\u0e1e\u0e31\u0e19\u0e2a\u0e38\u0e02 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 235\/1  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e34\u0e14\u0e23\u0e32\u0e0a\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138926\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e04\u0e22\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138926 \u0e1a\u0e08.\u0e20\u0e32\u0e04\u0e22\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e0d\u52d5\u7523 404  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1d\u0e31\u0e48\u0e07\u0e43\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138951\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e19\u0e4c\u0e40\u0e17\u0e23\u0e19\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138951 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e19\u0e4c\u0e40\u0e17\u0e23\u0e19\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 28  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 69 \u0e41\u0e22\u0e01 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138969\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138969 \u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 344  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 3 \u0e0b\u0e2d\u0e22 8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138993\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e19\u0e0b\u0e34\u0e2a \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138993 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e19\u0e0b\u0e34\u0e2a \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e04\u0e49\u0e19\u0e2b\u0e32 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e04\u0e34\u0e14\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e15\u0e23\u0e27\u0e08\u0e41\u0e01\u0e49 \u0e2d\u0e19\u0e38\u0e21\u0e31\u0e15\u0e34 \u0e08\u0e31\u0e14\u0e15\u0e32\u0e23\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e2a\u0e37\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e43\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 267\/207  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139043\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139043 \u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2d\u0e0b\u0e35\u0e17\u0e35 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/370  \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e1927 \u0e41\u0e22\u0e01 35 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139051\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e17\u0e4c\u0e2d\u0e31\u0e1e \u0e25\u0e35\u0e1f\u0e40\u0e27\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139051 \u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e17\u0e4c\u0e2d\u0e31\u0e1e \u0e25\u0e35\u0e1f\u0e40\u0e27\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 125   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 104 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 3 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139060\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64991\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64991\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139060 \u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 64991 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21 \u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e07\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 25\/19  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e42\u0e01\u0e29\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139132\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e34\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e40\u0e19\u0e4a\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139132 \u0e1a\u0e08.\u0e17\u0e34\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e40\u0e19\u0e4a\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 109  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e21\u0e31\u0e0a\u0e0c\u0e31\u0e19\u0e15\u0e34\u0e01\u0e32\u0e23\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139141\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e1f\u0e4c\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139141 \u0e1a\u0e08.\u0e44\u0e25\u0e1f\u0e4c\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e23\u0e23\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e01\u0e48\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e15\u0e23\u0e2d\u0e01\u0e28\u0e23\u0e35\u0e23\u0e31\u0e1a\u0e2a\u0e38\u0e02  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35 62 \u0e41\u0e22\u0e01 6-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139167\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e25\u0e34\u0e1f\u0e17\u0e4c\u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139167 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e25\u0e34\u0e1f\u0e17\u0e4c\u0e40\u0e17\u0e04 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e42\u0e1f\u0e25\u0e4c\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e16\u0e22\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32 (electric forklift) \u0e23\u0e16\u0e23\u0e35\u0e0a\u0e17\u0e23\u0e31\u0e04 (reach truck) \u0e23\u0e16\u0e22\u0e01\u0e1e\u0e32\u0e40\u0e25\u0e17 \u0e23\u0e16\u0e2a\u0e41\u0e15\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e25\u0e32\u0e01\u0e08\u0e39\u0e07 \u0e23\u0e16 vna \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e16\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/27  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 60 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139175\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e04\u0e34\u0e13\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139175 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e04\u0e34\u0e13\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 311\/34  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e32\u0e0b\u0e48\u0e32\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e14\u0e2d\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e34\u0e14\u0e23\u0e32\u0e0a\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139183\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49 \u0e14\u0e48\u0e27\u0e19\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139183 \u0e1a\u0e08.\u0e14\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49 \u0e14\u0e48\u0e27\u0e19\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e09\u0e25\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e39\u0e18 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u88fd\u9020 320\/207  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139191\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e14\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139191 \u0e1a\u0e08.\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e14\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 382  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e1919 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139205\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e25\u0e1f\u0e35\u0e48 \u0e40\u0e13\u0e27\u0e32\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139205 \u0e1a\u0e08.\u0e2e\u0e32\u0e25\u0e1f\u0e35\u0e48 \u0e40\u0e13\u0e27\u0e32\u0e2b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 2771\/32  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139248\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139248 \u0e1a\u0e08.\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a \u533b\u7642\u30fb\u798f\u7949 217\/3  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e40\u0e0a\u0e37\u0e2d\u0e01\u0e2b\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139264\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e35\u0e08\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139264 \u0e1a\u0e08.\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e21\u0e35\u0e08\u0e23\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 93111 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e23\u0e4c\u0e17\u0e41\u0e1a\u0e14\u0e21\u0e34\u0e19\u0e15\u0e31\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 745  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c71 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139272\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139272 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 30\/16  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e23\u0e27\u0e34\u0e20\u0e32\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139281\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e14\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139281 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e14\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 746 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139299\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e15\u0e25\u0e32\u0e2a \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139299 \u0e1a\u0e08.\u0e41\u0e2d\u0e15\u0e25\u0e32\u0e2a \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 745 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139302\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139302 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139311\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e31\u0e01\u0e17\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139311 \u0e1a\u0e08.\u0e2a\u0e31\u0e01\u0e17\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139353\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e25\u0e19 \u0e2a\u0e40\u0e1b\u0e0b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139353 \u0e1a\u0e08.\u0e41\u0e1e\u0e25\u0e19 \u0e2a\u0e40\u0e1b\u0e0b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 96  \u0e0b\u0e2d\u0e22 \u0e04\u0e38\u0e49\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 48 \u0e16\u0e19\u0e19\u0e04\u0e38\u0e49\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139361\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e01\u0e23\u0e2d\u0e21\u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139361 \u0e1a\u0e08.\u0e2d\u0e34\u0e01\u0e23\u0e2d\u0e21\u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e21\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e21\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 106\/1  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e04\u0e4c 80 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139388\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e40\u0e01\u0e34\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139388 \u0e1a\u0e08.\u0e40\u0e1a\u0e40\u0e01\u0e34\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e40\u0e40\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 69  \u0e16\u0e19\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139400\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e15\u0e32\u0e43\u0e2b\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139400 \u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e15\u0e32\u0e43\u0e2b\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 3656\/88  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e01\u0e23\u0e35\u0e19\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139418\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e40\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139418 \u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e40\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e42\u0e23\u0e04 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e09\u0e35\u0e14\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e15\u0e31\u0e14\u0e02\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e17\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 (lab) \u0e01\u0e32\u0e23\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e32\u0e0b\u0e32\u0e27\u0e19\u0e14\u0e4c \u0e2a\u0e31\u0e15\u0e27\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 407  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139442\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e0b\u0e35.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52299\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52299\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139442 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e0b\u0e35.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 52299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e41\u0e17\u0e49 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e23\u0e14\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e23\u0e14\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e48\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e38\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e04\u0e27\u0e32\u0e21\u0e04\u0e23\u0e1a\u0e16\u0e49\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e33\u0e2b\u0e19\u0e34\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 464\/67  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139451\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e32\u0e27\u0e14\u0e4c \u0e14\u0e34\u0e42\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139451 \u0e1a\u0e08.\u0e1e\u0e23\u0e32\u0e27\u0e14\u0e4c \u0e14\u0e34\u0e42\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e17\u0e2d\u0e07 \u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/83  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139469\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 666 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139469 \u0e1a\u0e08.\u0e19\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 666 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/16  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e1b\u0e17\u0e38\u0e21\u0e04\u0e07\u0e04\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139485\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e44\u0e17\u0e17\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139485 \u0e1a\u0e08.\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e44\u0e17\u0e17\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 43120 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e02\u0e38\u0e14 \u0e07\u0e32\u0e19\u0e40\u0e08\u0e32\u0e30 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e07\u0e32\u0e19\u0e16\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e1c\u0e49\u0e27\u0e16\u0e32\u0e07 \u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 16\/1  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139493\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139493 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 139   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 301-304 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e14\u0e2d\u0e30\u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e23\u0e31\u0e0a\u0e14\u0e32 \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139507\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e25\u0e41\u0e25\u0e19\u0e17\u0e4c \u0e1f\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"26109\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"26109\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139507 \u0e1a\u0e08.\u0e41\u0e01\u0e25\u0e41\u0e25\u0e19\u0e17\u0e4c \u0e1f\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 26109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e15\u0e25\u0e2d\u0e14\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e04\u0e34\u0e14\u0e04\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e39\u0e49\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e2a\u0e32\u0e02\u0e32 \u0e42\u0e21\u0e40\u0e14\u0e47\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 1053\/1  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139540\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e40\u0e1e\u0e47\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139540 \u0e1a\u0e08.\u0e17\u0e35 \u0e40\u0e1e\u0e47\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e15\u0e30 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 155\/29  \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e41\u0e22\u0e01 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139566\",\"name_th\":\"\u0e1a\u0e08.5\u0e2d \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139566 \u0e1a\u0e08.5\u0e2d \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 4565  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139574\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e44\u0e2d\u0e27\u0e35 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139574 \u0e1a\u0e08.\u0e17\u0e35\u0e44\u0e2d\u0e27\u0e35 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 3691  \u0e0b\u0e2d\u0e22 \u0e42\u0e22\u0e18\u0e34\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 11 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139582\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e14\u0e07 1988 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139582 \u0e1a\u0e08.\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e14\u0e07 1988 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 62\/138  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e27\u0e19\u0e0a\u0e21 \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 48 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139604\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e15\u0e23\u0e23\u0e27\u0e22 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139604 \u0e1a\u0e08.\u0e42\u0e04\u0e15\u0e23\u0e23\u0e27\u0e22 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 1732\/155  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024343\",\"name_th\":\"\u0e1a\u0e08.\u0e24\u0e17\u0e18\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024343 \u0e1a\u0e08.\u0e24\u0e17\u0e18\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e49\u0e27\u0e2d\u0e34\u0e19 (built-in furniture) \u88fd\u9020 89\/152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024351\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e41\u0e14\u0e19\u0e40\u0e1a\u0e2a\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024351 \u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e41\u0e14\u0e19\u0e40\u0e1a\u0e2a\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e0a\u0e21\u0e1e\u0e39\u0e2a\u0e23\u0e30\u0e1c\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e19\u0e27\u0e14\u0e1c\u0e21 \u0e2a\u0e1a\u0e39\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024378\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024378 \u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e25\u0e31\u0e14\u0e27\u0e07\u0e08\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5efa\u8a2d 388\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024394\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e0d\u0e32 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e14\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024394 \u0e1a\u0e08.\u0e44\u0e2d\u0e0d\u0e32 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e14\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 69\/128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024408\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1b\u0e20\u0e32 \u0e1a\u0e25\u0e39\u0e44\u0e2d\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024408 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1b\u0e20\u0e32 \u0e1a\u0e25\u0e39\u0e44\u0e2d\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e2b\u0e25\u0e2d\u0e14\u0e40\u0e25\u0e47\u0e01  \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e2b\u0e25\u0e2d\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e0b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 564  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024416\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024416 \u0e1a\u0e08.\u0e40\u0e04.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 59\/365  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024424\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34 \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024424 \u0e1a\u0e08.\u0e21\u0e34 \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 111\/190  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17\u0e41\u0e1a\u0e23\u0e34\u0e48\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024432\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024432 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 335\/195  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024441\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e1b\u0e1c\u0e32 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024441 \u0e1a\u0e08.\u0e1a\u0e38\u0e1b\u0e1c\u0e32 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 756  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024467\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e0a\u0e32\u0e22\u0e02\u0e32\u0e22\u0e16\u0e38\u0e07 1998 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024467 \u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e0a\u0e32\u0e22\u0e02\u0e32\u0e22\u0e16\u0e38\u0e07 1998 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 22299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 453\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024475\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46422\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46422\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024475 \u0e1a\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46422 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e2b\u0e25\u0e2d\u0e14\u0e44\u0e1f\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/55,57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027687\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e27\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027687 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e27\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e17\u0e32\u0e07\u0e25\u0e32\u0e14\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 123\/81  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e215 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027695\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e1f\u0e32\u0e22\u0e14\u0e4c \u0e27\u0e35\u0e40\u0e17\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027695 \u0e1a\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e1f\u0e32\u0e22\u0e14\u0e4c \u0e27\u0e35\u0e40\u0e17\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e14\u0e19\u0e15\u0e23\u0e35 (festival) \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 114\/155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027709\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e0a\u0e34 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027709 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e0a\u0e34 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e38\u0e49\u0e21 \u0e1a\u0e39\u0e18 \u0e40\u0e27\u0e17\u0e35 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 10\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22-\u0e27\u0e31\u0e14\u0e15\u0e49\u0e19\u0e40\u0e0a\u0e37\u0e2d\u0e01 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027717\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e14\u0e35 \u0e2d\u0e34\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027717 \u0e1a\u0e08.\u0e14\u0e39\u0e14\u0e35 \u0e2d\u0e34\u0e19\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 54\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027733\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e34\u0e25\u0e34\u0e19 \u0e2d\u0e30\u0e1e\u0e32\u0e40\u0e23\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027733 \u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e34\u0e25\u0e34\u0e19 \u0e2d\u0e30\u0e1e\u0e32\u0e40\u0e23\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 14112 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e07\u0e32\u0e19\u0e1b\u0e31\u0e01 \u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e07\u0e32\u0e19\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a (sample) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e42\u0e25\u0e42\u0e01\u0e49 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1b\u0e49\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e04\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e09\u0e25\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 57\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027768\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e0d\u0e0a\u0e38\u0e21\u0e32\u0e2a2445 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027768 \u0e1a\u0e08.\u0e21\u0e31\u0e0d\u0e0a\u0e38\u0e21\u0e32\u0e2a2445 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 74109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e31\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a \u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 58\/26 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027776\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027776 \u0e1a\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e25\u0e34\u0e40\u0e18\u0e35\u0e22\u0e21  \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027784\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93292\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93292\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027784 \u0e1a\u0e08.\u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 93292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c  \u0e42\u0e23\u0e07\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c  \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e\u0e2d\u0e37\u0e48\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32  \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e42\u0e1a\u0e27\u0e4c\u0e25\u0e34\u0e48\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 70  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 19 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027806\",\"name_th\":\"\u0e1a\u0e08. \u0e1e\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 99 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027806 \u0e1a\u0e08. \u0e1e\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 99 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/223  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 25 \u0e41\u0e22\u0e01 26 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027822\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e19\u0e08\u0e35\u0e49  \u0e04\u0e32\u0e23\u0e4c\u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027822 \u0e1a\u0e08.\u0e40\u0e1a\u0e19\u0e08\u0e35\u0e49  \u0e04\u0e32\u0e23\u0e4c\u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45203 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/385  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002615\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e34\u0e27 \u0e10\u0e32\u0e19\u0e44\u0e1e\u0e28\u0e32\u0e25\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002615 \u0e2b\u0e08.\u0e08\u0e34\u0e27 \u0e10\u0e32\u0e19\u0e44\u0e1e\u0e28\u0e32\u0e25 2569-07-23 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01 \u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022715\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e1e\u0e23\u0e35\u0e21 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022715 \u0e1a\u0e08.\u0e0b\u0e39\u0e1e\u0e23\u0e35\u0e21 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 55\/71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022731\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e21\u0e32\u0e14\u0e35 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022731 \u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e21\u0e32\u0e14\u0e35 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 111\/16  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e27\u0e19\u0e34\u0e27 \u0e44\u0e2d\u0e14\u0e35 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19-\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022774\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32 \u0e21\u0e2b\u0e32\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022774 \u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32 \u0e21\u0e2b\u0e32\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e19\u0e31\u0e01\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e43\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23 \u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 55\/242  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022804\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e14\u0e23\u0e31\u0e07\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022804 \u0e1a\u0e08.\u0e01\u0e31\u0e14\u0e23\u0e31\u0e07\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 27\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022812\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e07\u0e04\u0e4c \u0e42\u0e1f\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022812 \u0e1a\u0e08.\u0e27\u0e34\u0e07\u0e04\u0e4c \u0e42\u0e1f\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/1157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004806\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004806 \u0e1a\u0e08.\u0e1e\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 109\/427  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004814\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e30 \u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004814 \u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e30 \u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 109\/427  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001700\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e35\u0e48 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001700 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e35\u0e48 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 339\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001718\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e24\u0e29 \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001718 \u0e1a\u0e08.\u0e01\u0e24\u0e29 \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u5efa\u8a2d 556\/73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001726\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e19\u0e2a\u0e34\u0e23\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001726 \u0e1a\u0e08.\u0e21\u0e19\u0e2a\u0e34\u0e23\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 202\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0185569000517\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e0a\u0e48\u0e32\u0e07\u0e40\u0e01\u0e48\u0e07 \u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0185569000517 \u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e0a\u0e48\u0e32\u0e07\u0e40\u0e01\u0e48\u0e07 \u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e01\u0e25\u0e36\u0e07 \u0e23\u0e31\u0e1a\u0e01\u0e25\u0e36\u0e07 \u0e44\u0e2a \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e15\u0e31\u0e14 \u0e40\u0e08\u0e32\u0e30 \u0e2b\u0e25\u0e48\u0e2d \u0e2b\u0e25\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e42\u0e25\u0e2b\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u88fd\u9020 112\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0203569003238\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003238 \u0e2b\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49 2569-07-23 1000000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e23\u0e35\u0e14\u0e1c\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e1e\u0e25\u0e39\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 26\/207  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003246\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003246 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-23 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21            \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 144\/165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038564\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e04 \u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038564 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e04 \u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038572\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038572 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038581\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e04\u0e39\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038581 \u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e04\u0e39\u0e25\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e41\u0e2d\u0e23\u0e4c \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e25\u0e49\u0e32\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038599\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e25\u0e40\u0e25\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038599 \u0e1a\u0e08.\u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e25\u0e40\u0e25\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e19\u0e49\u0e33\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e41\u0e25\u0e30\u0e02\u0e19\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038602\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e0b\u0e35\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038602 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e0b\u0e35\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038629\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e10\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038629 \u0e1a\u0e08.\u0e13\u0e10\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e22\u0e37\u0e14 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e31\u0e19\u0e1e\u0e32\u0e40\u0e25\u0e17 \u0e1e\u0e32\u0e40\u0e25\u0e17\u0e44\u0e21\u0e49 \u0e1e\u0e32\u0e40\u0e25\u0e17\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e17\u0e1b\u0e01\u0e32\u0e27 \u0e01\u0e32\u0e27\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d \u0e16\u0e38\u0e07\u0e02\u0e22\u0e30 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 238\/384  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e1f\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e17\u0e32\u0e27\u0e19\u0e4c 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038637\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e2d\u0e35 \u0e40\u0e08 \u0e40\u0e14\u0e25\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038637 \u0e1a\u0e08.\u0e42\u0e2d\u0e2d\u0e35 \u0e40\u0e08 \u0e40\u0e14\u0e25\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e07 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07            \u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e16\u0e48\u0e32\u0e22\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (product photography)             \u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e14\u0e49\u0e27\u0e22\u0e42\u0e14\u0e23\u0e19             (\u0e1c\u0e39\u0e49\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14 (live streaming) \u0e1c\u0e25\u0e34\u0e15\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a tiktok, facebook,             instagram \u0e41\u0e25\u0e30 youtube \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 114\/114  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e1a\u0e32\u0e42\u0e04\u0e25\u0e19\u0e35\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038688\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e1a\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038688 \u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e1a\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 323\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038696\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e19\u0e0b\u0e48\u0e32 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038696 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e19\u0e0b\u0e48\u0e32 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 (it infrastructure) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 678\/460   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 102 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038700\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e18\u0e34\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038700 \u0e1a\u0e08.\u0e2d\u0e18\u0e34\u0e17\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e16\u0e21\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 30\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038793\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e27\u0e35\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038793 \u0e1a\u0e08.\u0e17\u0e27\u0e35\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/174, 20\/175  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2e\u0e2d\u0e25\u0e34\u0e40\u0e14\u0e22\u0e4c\u0e42\u0e2e\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e43\u0e15\u0e49 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001341\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e32\u0e19\u0e34\u0e0a\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11049\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11049\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001341 \u0e2b\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e32\u0e19\u0e34\u0e0a 2569-07-23 1000000 11049 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e21\u0e35\u0e48\u0e40\u0e2a\u0e27\u0e35\u0e48\u0e22 ( mixue ) \u88fd\u9020 105\/7  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e18\u0e23\u0e32\u0e19\u0e31\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009785\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35\u0e1e\u0e35 \u0e41\u0e1e\u0e47\u0e04\u0e01\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009785 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35\u0e1e\u0e35 \u0e41\u0e1e\u0e47\u0e04\u0e01\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e32\u0e40\u0e25\u0e17\u0e44\u0e21\u0e49\u0e1e\u0e32\u0e40\u0e25\u0e17\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e32\u0e40\u0e25\u0e17\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e25\u0e31\u0e07\u0e44\u0e21\u0e49 \u0e25\u0e31\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e25\u0e31\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 268  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009793\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009793 \u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e09\u0e35\u0e14 \u0e41\u0e25\u0e30\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e42\u0e1e\u0e23\u0e1e\u0e34\u0e25\u0e35 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e42\u0e1f\u0e21\u0e41\u0e1c\u0e48\u0e19\u0e2d\u0e35\u0e1e\u0e35\u0e2d\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 555\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009815\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e27\u0e14\u0e35\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009815 \u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e27\u0e14\u0e35\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 57\/39  \u0e16\u0e19\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1c\u0e483 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002349\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e25\u0e25\u0e39\u0e19 \u0e40\u0e2e\u0e27\u0e35\u0e48\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002349 \u0e1a\u0e08.\u0e1a\u0e2d\u0e25\u0e25\u0e39\u0e19 \u0e40\u0e2e\u0e27\u0e35\u0e48\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e38\u0e14\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e08\u0e32\u0e30\u0e1a\u0e48\u0e2d\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e08\u0e32\u0e30\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e14\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002357\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e35\u0e48 \u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002357 \u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e35\u0e48 \u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0243569000743\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e44\u0e21\u0e25\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000743 \u0e2b\u0e08.\u0e2a\u0e44\u0e21\u0e25\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 2569-07-23 1000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0243569000751\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e35\u0e1f\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e14\u0e47\u0e01\u0e2d\u0e48\u0e2d\u0e19\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000751 \u0e2b\u0e08.\u0e21\u0e35\u0e1f\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e14\u0e47\u0e01\u0e2d\u0e48\u0e2d\u0e19 2569-07-23 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003990\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e41\u0e1b\u0e14 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003990 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e41\u0e1b\u0e14 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 78109 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e17\u0e33\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 111\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002110\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002110 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 35\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0273569000476\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35.\u0e27\u0e32\u0e22.\u0e40\u0e04 1661\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0273569000476 \u0e2b\u0e08.\u0e1e\u0e35.\u0e27\u0e32\u0e22.\u0e40\u0e04 1661 2569-07-23 1000000 45101 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/1  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 18 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002893\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e27\u0e35\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 168\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002893 \u0e2b\u0e08.\u0e17\u0e27\u0e35\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 168 2569-07-23 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002907\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e2b\u0e4c\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002907 \u0e2b\u0e08.\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e2b\u0e4c\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-23 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007633\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 24 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007633 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 24 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 263  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e 15 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007641\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e0a\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007641 \u0e1a\u0e08.\u0e17\u0e35 \u0e0a\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 (delivery) \u5bbf\u6cca\u30fb\u98f2\u98df 108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001129\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e27\u0e32\u0e22 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 1988\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001129 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e27\u0e32\u0e22 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 1988 2569-07-23 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 75\/3-4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569001996\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001996 \u0e1a\u0e08.\u0e44\u0e2d\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22-\u0e0b\u0e48\u0e2d\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 550\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569002003\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e21\u0e34\u0e40\u0e25\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569002003 \u0e1a\u0e08.\u0e04\u0e32\u0e21\u0e34\u0e40\u0e25\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 183  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e1b\u0e23\u0e37\u0e2d \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0345569003344\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e01\u0e23 \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25 1994 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003344 \u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e01\u0e23 \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25 1994 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003361\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e2a\u0e15\u0e35\u0e25 \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003361 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e2a\u0e15\u0e35\u0e25 \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0365569001473\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e15\u0e04\u0e38\u0e13 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001473 \u0e1a\u0e08.\u0e40\u0e15\u0e04\u0e38\u0e13 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e14\u0e39\u0e41\u0e25 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 256  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0385569000531\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21. 299 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000531 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21. 299 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007080\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e192020 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007080 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e192020 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 151\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007110\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e47\u0e14\u0e14\u0e27\u0e07\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007110 \u0e1a\u0e08.\u0e40\u0e14\u0e47\u0e14\u0e14\u0e27\u0e07\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e38\u0e01\u0e35\u0e49 \u0e0a\u0e32\u0e1a\u0e39 \u0e41\u0e08\u0e48\u0e27\u0e2e\u0e49\u0e2d\u0e19 \u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e1f \u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u0e17\u0e2d\u0e14 \u0e19\u0e36\u0e48\u0e07 \u0e15\u0e49\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e41\u0e1a\u0e1a\u0e08\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e08\u0e32\u0e19 (a-la-cart) \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e15\u0e4b \u5bbf\u6cca\u30fb\u98f2\u98df 255  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003921\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e32\u0e23\u0e31\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003921 \u0e1a\u0e08.\u0e17\u0e32\u0e23\u0e31\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u91d1\u878d\u30fb\u4fdd\u967a 555\/129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0455569001537\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e23\u0e32\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001537 \u0e1a\u0e08.\u0e40\u0e25\u0e23\u0e32\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e41\u0e2a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0465569000913\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e1e\u0e18\u0e32\u0e19\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000913 \u0e1a\u0e08.\u0e20\u0e1e\u0e18\u0e32\u0e19\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0475569001651\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001651 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 208  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005149\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e2a\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005149 \u0e2b\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e2a 2569-07-23 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 428\/47  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e38\u0e48\u0e07\u0e18\u0e19\u0e32 7 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569005165\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e15\u0e32\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005165 \u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e15\u0e32\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-23 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0a\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e40\u0e2a\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 231  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016576\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e4a\u0e32 \u0e1b\u0e4b\u0e2d \u0e01\u0e31\u0e2a \u0e40\u0e15\u0e34\u0e4b\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016576 \u0e1a\u0e08.\u0e40\u0e01\u0e4a\u0e32 \u0e1b\u0e4b\u0e2d \u0e01\u0e31\u0e2a \u0e40\u0e15\u0e34\u0e4b\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e16\u0e42\u0e01\u0e04\u0e32\u0e23\u0e4c\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 20\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001463\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e01\u0e34\u0e08\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001463 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e01\u0e34\u0e08\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001722\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001722 \u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 754  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001731\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e34\u0e19\u0e1e\u0e32\u0e40\u0e25\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001731 \u0e1a\u0e08.\u0e2a\u0e01\u0e34\u0e19\u0e1e\u0e32\u0e40\u0e25\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 754  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001749\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e42\u0e19\u0e14\u0e23\u0e34\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001749 \u0e1a\u0e08.\u0e42\u0e21\u0e42\u0e19\u0e14\u0e23\u0e34\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e19\u0e49\u0e33\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e41\u0e25\u0e30\u0e02\u0e19\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 754  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001757\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e2a\u0e34\u0e15\u0e32 \u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001757 \u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e2a\u0e34\u0e15\u0e32 \u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 208\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001765\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e1e\u0e23\u0e27\u0e23\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001765 \u0e1a\u0e08.\u0e23\u0e32\u0e1e\u0e23\u0e27\u0e23\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 559  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e25\u0e33\u0e1b\u0e32\u0e07-\u0e41\u0e21\u0e48\u0e17\u0e30 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0533569000546\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e31\u0e04\u0e1e\u0e07\u0e28\u0e4c \u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0533569000546 \u0e2b\u0e08.\u0e20\u0e31\u0e04\u0e1e\u0e07\u0e28\u0e4c \u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-23 1000000 46530 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e16\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e2b\u0e22\u0e2d\u0e14\u0e02\u0e49\u0e32\u0e27 \u0e23\u0e16\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0545569000840\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e42\u0e19\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000840 \u0e1a\u0e08.\u0e23\u0e34\u0e42\u0e19\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 14  \u0e0b\u0e2d\u0e22 2 (\u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e48\u0e27\u0e07) \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0545569000858\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000858 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 84\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0575569004802\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e01\u0e1a\u0e32 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004802 \u0e1a\u0e08.\u0e40\u0e23\u0e01\u0e1a\u0e32 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e1a\u0e48\u0e07\u0e41\u0e22\u0e01 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u4e0d\u52d5\u7523 244  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e38\u0e48\u0e07\u0e23\u0e27\u0e07\u0e17\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004829\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e42\u0e21\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004829 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e42\u0e21\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 406\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001681\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e04\u0e1a\u0e35343\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001681 \u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e04\u0e1a\u0e35343 2569-07-23 1000000 47640 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001690\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e35\u0e21\u0e35\u0e21\u0e32\u0e21\u0e32\u0e01\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001690 \u0e2b\u0e08.\u0e21\u0e35\u0e21\u0e35\u0e21\u0e32\u0e21\u0e32\u0e01 2569-07-23 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001711\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e1a\u0e35\u0e1a\u0e35\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001711 \u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e1a\u0e35\u0e1a\u0e35 2569-07-23 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0615569000601\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e40\u0e17\u0e1e\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10795\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10795\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000601 \u0e1a\u0e08.\u0e01\u0e23\u0e40\u0e17\u0e1e\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 10795 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e42\u0e23\u0e07\u0e2a\u0e35 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e38\u0e23\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u88fd\u9020 69\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0633569000782\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e32\u0e27\u0e32\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000782 \u0e2b\u0e08.\u0e25\u0e32\u0e27\u0e32\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-23 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/11  \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e2a\u0e25\u0e32\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0645569000776\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000776 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 235\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0655569002388\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e27\u0e32 \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002388 \u0e1a\u0e08.\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e27\u0e32 \u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/66  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e4c \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 6 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0675569001578\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e38\u0e19\u0e40\u0e02\u0e32 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001578 \u0e1a\u0e08.\u0e02\u0e38\u0e19\u0e40\u0e02\u0e32 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003332\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003332 \u0e1a\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003341\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e04\u0e2d\u0e30\u0e1a\u0e31\u0e2a \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003341 \u0e1a\u0e08.\u0e40\u0e21\u0e04\u0e2d\u0e30\u0e1a\u0e31\u0e2a \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07 \u0e40\u0e04\u0e32\u0e30\u0e1b\u0e30\u0e1c\u0e38 \u0e17\u0e33\u0e2a\u0e35 \u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 64\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002760\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38212\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38212\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002760 \u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 38212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e15\u0e32\u0e40\u0e1c\u0e32\u0e02\u0e22\u0e30 \u0e40\u0e15\u0e32\u0e40\u0e1c\u0e32\u0e02\u0e22\u0e30\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e04\u0e27\u0e31\u0e19 \u0e40\u0e15\u0e32\u0e40\u0e1c\u0e32\u0e02\u0e22\u0e30\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e40\u0e15\u0e32\u0e40\u0e1c\u0e32\u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25 \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 54\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002191\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002191 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46530 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e23\u0e16\u0e15\u0e31\u0e14\u0e2d\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 224\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007451\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e04\u0e0b\u0e35 \u0e0b\u0e35\u0e27\u0e34\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007451 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e04\u0e0b\u0e35 \u0e0b\u0e35\u0e27\u0e34\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 17\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007460\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007460 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e23\u0e35\u0e21\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 (coconut cream concentrate) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007796\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e4a\u0e2d\u0e1b \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007796 \u0e1a\u0e08.\u0e17\u0e4a\u0e2d\u0e1b \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e33\u0e19\u0e27\u0e13\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 (solar rooftop) \u0e1a\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19 (solar farm) \u0e41\u0e25\u0e30\u0e1a\u0e19\u0e1c\u0e34\u0e27\u0e19\u0e49\u0e33 (solar floating) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 18\/105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007800\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19\u0e2d\u0e2d\u0e1f\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007800 \u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19\u0e2d\u0e2d\u0e1f\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33          \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/84  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007818\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08.\u0e1e\u0e35.\u0e42\u0e1f\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007818 \u0e1a\u0e08.\u0e40\u0e08.\u0e1e\u0e35.\u0e42\u0e1f\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46699 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e42\u0e1f\u0e21 \u0e40\u0e17\u0e1b\u0e2a\u0e35 \u0e16\u0e38\u0e07\u0e2b\u0e39\u0e2b\u0e34\u0e49\u0e27 \u0e16\u0e38\u0e07\u0e25\u0e2d\u0e07\u0e42\u0e1f\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e1e\u0e47\u0e04\u0e42\u0e1f\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007826\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e49\u0e19\u0e14\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e1f\u0e34\u0e25\u0e40\u0e17\u0e23\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45303\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45303\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007826 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e49\u0e19\u0e14\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e1f\u0e34\u0e25\u0e40\u0e17\u0e23\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16 \u0e40\u0e0a\u0e48\u0e19\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e41\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007869\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e0b\u0e35\u0e40\u0e04\u0e23\u0e47\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007869 \u0e1a\u0e08.\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e0b\u0e35\u0e40\u0e04\u0e23\u0e47\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e15\u0e31\u0e4b\u0e27\u0e08\u0e33\u0e19\u0e33\u0e17\u0e2d\u0e07 \u91d1\u878d\u30fb\u4fdd\u967a 81\/121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007885\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007885 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e01\u0e48\u0e32 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e02\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e40\u0e28\u0e29\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e28\u0e29\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0765569001518\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e04\u0e25\u0e32\u0e2a \u0e41\u0e27\u0e19 \u0e2d\u0e2d\u0e1b\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001518 \u0e1a\u0e08.\u0e2d\u0e34\u0e04\u0e25\u0e32\u0e2a \u0e41\u0e27\u0e19 \u0e2d\u0e2d\u0e1b\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0805569002874\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e2d\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002874 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e2d\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 34  \u0e0b\u0e2d\u0e22 \u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 2 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23-\u0e1b\u0e32\u0e01\u0e1e\u0e19\u0e31\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013566\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e25\u0e32\u0e07 5 \u0e14\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013566 \u0e1a\u0e08.\u0e16\u0e25\u0e32\u0e07 5 \u0e14\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e44\u0e01\u0e48\u0e22\u0e48\u0e32\u0e07 \u0e44\u0e01\u0e48\u0e17\u0e2d\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e35\u0e22\u0e07 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 33\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013574\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e25\u0e32\u0e07 \u0e40\u0e08 \u0e27\u0e2d\u0e0a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013574 \u0e1a\u0e08.\u0e16\u0e25\u0e32\u0e07 \u0e40\u0e08 \u0e27\u0e2d\u0e0a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e14\u0e39\u0e14\u0e1d\u0e38\u0e48\u0e19 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e02\u0e31\u0e14\u0e2a\u0e35 \u0e02\u0e31\u0e14\u0e44\u0e1f\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 33\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013582\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e04\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e1a\u0e04\u0e4c \u0e40\u0e23\u0e19\u0e40\u0e17\u0e34\u0e25 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013582 \u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e04\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e1a\u0e04\u0e4c \u0e40\u0e23\u0e19\u0e40\u0e17\u0e34\u0e25 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 10\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013591\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e23\u0e4c\u0e17\u0e27\u0e39\u0e14 \u0e2e\u0e32\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013591 \u0e1a\u0e08.\u0e2e\u0e32\u0e23\u0e4c\u0e17\u0e27\u0e39\u0e14 \u0e2e\u0e32\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 6\/62  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e19\u0e17\u0e23 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013604\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e23\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013604 \u0e1a\u0e08.\u0e40\u0e21\u0e23\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27 \u5efa\u8a2d 40\/55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013612\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47822\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47822\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013612 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e48\u0e32\u0e27\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 47822 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e15\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 \u0e43\u0e0a\u0e49\u0e2a\u0e2d\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 209\/15  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 200 \u0e1b\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013621\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e23\u0e1f\u0e34\u0e0a\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013621 \u0e1a\u0e08.\u0e40\u0e04\u0e23\u0e1f\u0e34\u0e0a\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e38\u0e49\u0e07\u0e40\u0e04\u0e23\u0e1f\u0e34\u0e0a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 84\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010800\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e \u0e44\u0e25\u0e1f\u0e4c \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010800 \u0e1a\u0e08.\u0e44\u0e2e \u0e44\u0e25\u0e1f\u0e4c \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 85\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0855569000561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e272005 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000561 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e272005 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001282\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25 \u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001282 \u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25 \u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e25\u0e33\u0e43\u0e22 \u0e40\u0e07\u0e32\u0e30 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 174  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001291\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001291 \u0e1a\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1b\u0e38\u0e4b\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e34\u0e19\u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e22\u0e32\u0e06\u0e48\u0e32\u0e41\u0e21\u0e25\u0e07 \u0e22\u0e32\u0e06\u0e48\u0e32\u0e2b\u0e19\u0e39  \u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e23\u0e32 \u0e22\u0e32\u0e17\u0e33\u0e25\u0e32\u0e22\u0e27\u0e31\u0e0a\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 211  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569006089\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e31\u0e21\u0e21\u0e35\u0e48 \u0e22\u0e4a\u0e32\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006089 \u0e1a\u0e08.\u0e22\u0e31\u0e21\u0e21\u0e35\u0e48 \u0e22\u0e4a\u0e32\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 50\/6  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e20\u0e39\u0e27\u0e19\u0e32\u0e23\u0e16 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006097\",\"name_th\":\"\u0e1a\u0e08.168\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006097 \u0e1a\u0e08.168\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 117\/2  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e19\u0e34\u0e0a \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006119\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e48\u0e33\u0e01\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b 1965 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006119 \u0e1a\u0e08.\u0e19\u0e48\u0e33\u0e01\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b 1965 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 46108 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 (\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07) \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e2b\u0e34\u0e19\u0e25\u0e31\u0e1a\u0e21\u0e35\u0e14\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 32 \u0e0b\u0e2d\u0e22 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006127\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006127 \u0e1a\u0e08.\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e41\u0e25\u0e30 \u0e40\u0e2d\u0e01\u0e0a\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 18\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0963569000313\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35.\u0e2d\u0e32\u0e23\u0e4c. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  2026\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000313 \u0e2b\u0e08.\u0e14\u0e35.\u0e2d\u0e32\u0e23\u0e4c. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  2026 2569-07-23 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569007889\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08 \u0e2d\u0e31\u0e25\u0e15\u0e23\u0e49\u0e32\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007889 \u0e2b\u0e08.\u0e27\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08 \u0e2d\u0e31\u0e25\u0e15\u0e23\u0e49\u0e32\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-22 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19 \u0e44\u0e2a\u0e49\u0e01\u0e23\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e0b\u0e2d\u0e22 \u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c 45 \u0e41\u0e22\u0e01 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007897\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e31\u0e27 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007897 \u0e2b\u0e08.\u0e1a\u0e31\u0e27 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 2569-07-22 1000000 74200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b  \u0e25\u0e49\u0e32\u0e07  \u0e2d\u0e31\u0e14  \u0e02\u0e22\u0e32\u0e22\u0e23\u0e39\u0e1b  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 295  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e25\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007901\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e07\u0e32\u0e2188\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007901 \u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e07\u0e32\u0e2188 2569-07-22 1000000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 333\/79  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 3 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137687\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e42\u0e22 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137687 \u0e1a\u0e08.\u0e19\u0e32\u0e42\u0e22 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e40\u0e1e\u0e08 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e21\u0e48\u0e02\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e02\u0e48\u0e32\u0e22 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 (crm) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 74\/4  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 54\/1 \u0e41\u0e22\u0e01 4-5 (\u0e15\u0e25\u0e32\u0e14 2) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137695\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137695 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 17  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e224 \u0e41\u0e22\u0e0130 \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e224 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137709\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e42\u0e2d\u0e0b\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137709 \u0e1a\u0e08.\u0e04\u0e34\u0e42\u0e2d\u0e0b\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 105\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e2d\u0e07\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e0a\u0e48 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e1e\u0e32\u0e23\u0e4c\u0e04  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e2d\u0e35104 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137725\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137725 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 71202 \u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 55\/15  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e2250 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137733\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e23\u0e30\u0e2d\u0e36\u0e49\u0e07\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47511\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47511\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137733 \u0e1a\u0e08.\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e23\u0e30\u0e2d\u0e36\u0e49\u0e07\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47511 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e1c\u0e49\u0e32 \u0e14\u0e49\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e08\u0e32\u0e01\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 117\/115  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 47 \u0e41\u0e22\u0e01 6 (\u0e0a\u0e34\u0e19\u0e40\u0e02\u0e15 2\/6) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137741\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e27\u0e32\u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137741 \u0e1a\u0e08.\u0e19\u0e32\u0e27\u0e32\u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30 \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1991  \u0e0b\u0e2d\u0e22 \u0e2d\u0e23\u0e38\u0e13\u0e2d\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c 57 \u0e16\u0e19\u0e19\u0e2d\u0e23\u0e38\u0e13\u0e2d\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137750\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137750 \u0e1a\u0e08.\u0e22\u0e39 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u5efa\u8a2d 81\/105  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e1e\u0e23\u0e35\u0e40\u0e27\u0e48 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 66 \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 66 \u0e41\u0e22\u0e01 19 \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137768\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e22\u0e38 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137768 \u0e1a\u0e08.\u0e1e\u0e32\u0e22\u0e38 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 836\/32  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e17\u0e32\u0e22 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e08\u0e23\u0e34\u0e0d 29 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137784\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e25\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e01 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137784 \u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e25\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e01 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 153  \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d33 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137806\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2a \u0e40\u0e17\u0e23\u0e14 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137806 \u0e1a\u0e08.\u0e40\u0e1a\u0e2a \u0e40\u0e17\u0e23\u0e14 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46109 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/8  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e23\u0e34\u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 80 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137814\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e41\u0e2d\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137814 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e41\u0e2d\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (logistics activities) \u904b\u8f38\u30fb\u7269\u6d41 102\/28  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 33 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137849\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137849 \u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e22\u0e48\u0e2d\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 208  \u0e2d\u0e32\u0e04\u0e32\u0e23208 \u0e41\u0e1a\u0e07\u0e04\u0e4a\u0e2d\u0e01  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 501 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137857\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e37\u0e2d\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137857 \u0e1a\u0e08.\u0e40\u0e2a\u0e37\u0e2d\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e09\u0e25\u0e32\u0e01 \u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e42\u0e1a\u0e27\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 88\/16  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137911\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e1b\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137911 \u0e1a\u0e08.\u0e25\u0e39\u0e1b\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 295\/72  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137946\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e42\u0e23\u0e30 \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137946 \u0e1a\u0e08.\u0e04\u0e34\u0e42\u0e23\u0e30 \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 36  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 21 (\u0e19\u0e27\u0e28\u0e23\u0e35) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137989\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137989 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e25\u0e30\u0e04\u0e19\u0e14\u0e39\u0e41\u0e25 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e44\u0e02\u0e49,\u0e1c\u0e39\u0e49\u0e40\u0e08\u0e47\u0e1a\u0e1b\u0e48\u0e27\u0e22\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u533b\u7642\u30fb\u798f\u7949 10\/102  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 13(\u0e41\u0e2a\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138021\",\"name_th\":\"\u0e1a\u0e08.20\u0e04\u0e2d\u0e22\u0e19\u0e4c\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138021 \u0e1a\u0e08.20\u0e04\u0e2d\u0e22\u0e19\u0e4c\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47739 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e15\u0e39\u0e49\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 751  \u0e0b\u0e2d\u0e22 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138047\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e1a\u0e23\u0e1f \u0e1f\u0e39\u0e4a\u0e14\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e23\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138047 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e1a\u0e23\u0e1f \u0e1f\u0e39\u0e4a\u0e14\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e23\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/18  \u0e16\u0e19\u0e19\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138055\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138055 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1\/94  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e2d\u0e2d\u0e23\u0e4c\u0e04\u0e34\u0e14\u0e1b\u0e32\u0e23\u0e4c\u0e04 2 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138063\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e34\u0e1f\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138063 \u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e34\u0e1f\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 88\/6  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138080\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e25\u0e30\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22230\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22230\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138080 \u0e1a\u0e08.\u0e0a\u0e32\u0e25\u0e30\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 22230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2b\u0e25\u0e48\u0e2d \u0e2b\u0e25\u0e2d\u0e21 \u0e09\u0e35\u0e14 \u0e41\u0e25\u0e30\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e23\u0e0b\u0e34\u0e19 \u0e04\u0e2d\u0e21\u0e42\u0e1e\u0e2a\u0e34\u0e15 \u0e42\u0e25\u0e2b\u0e30  \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e1a\u0e22\u0e36\u0e14 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 97\/219  \u0e0b\u0e2d\u0e22 \u0e42\u0e01\u0e2a\u0e38\u0e21\u0e23\u0e27\u0e21\u0e43\u0e08 39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138101\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138101 \u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e42\u0e2d\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 450\/22  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 50 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138128\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35\u0e48 15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138128 \u0e1a\u0e08.\u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35\u0e48 15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 64202 \u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u91d1\u878d\u30fb\u4fdd\u967a 35  \u0e0b\u0e2d\u0e22 \u0e41\u0e22\u0e01\u0e0b\u0e2d\u0e22\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138179\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e22\u0e39 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138179 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e22\u0e39 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/283  \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138187\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e25 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55109\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55109\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138187 \u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e25 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 55109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e44\u0e17\u0e21\u0e4c\u0e41\u0e0a\u0e23\u0e4c \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e27\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e1a\u0e1a\u0e0a\u0e32\u0e40\u0e25\u0e15\u0e4c \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e41\u0e02\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e31\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14 \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e14\u0e49\u0e32\u0e19\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 117\/18  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 47 \u0e41\u0e22\u0e01 6 (\u0e0a\u0e34\u0e19\u0e40\u0e02\u0e15 2\/6) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138195\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e21\u0e19\u0e35\u0e0b\u0e31\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138195 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e21\u0e19\u0e35\u0e0b\u0e31\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70  \u0e0b\u0e2d\u0e22 \u0e41\u0e21\u0e48\u0e40\u0e19\u0e35\u0e49\u0e22\u0e27 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138209\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e39\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138209 \u0e1a\u0e08.\u0e19\u0e39\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 28299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e01\u0e36\u0e48\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e19\u0e33\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e25\u0e32\u0e14\u0e15\u0e23\u0e30\u0e40\u0e27\u0e19 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e2d\u0e07\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e42\u0e15\u0e49\u0e15\u0e2d\u0e1a\u0e44\u0e14\u0e49 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 55  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d.\u0e40\u0e2d.\u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e23\u0e31\u0e0a\u0e14\u0e32 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138217\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e27\u0e31\u0e19\u0e14\u0e35345 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138217 \u0e1a\u0e08.\u0e14\u0e35\u0e27\u0e31\u0e19\u0e14\u0e35345 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/2046  \u0e0b\u0e2d\u0e22 \u0e21.\u0e1e\u0e07\u0e29\u0e4c\u0e28\u0e34\u0e23\u0e34\u0e0a\u0e31\u0e22 4 \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138225\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e40\u0e1e\u0e47\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138225 \u0e1a\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e40\u0e1e\u0e47\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e15\u0e31\u0e14\u0e02\u0e19 \u0e2a\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 346  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 40 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138233\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138233 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 14111 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 207  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 51 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138241\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e21 \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138241 \u0e1a\u0e08.\u0e0a\u0e34\u0e21 \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 66  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 31 (\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138250\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e42\u0e2e \u0e40\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138250 \u0e1a\u0e08.\u0e40\u0e25\u0e42\u0e2e \u0e40\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 25999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e25\u0e2b\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 7  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e1e\u0e2d\u0e22\u0e17\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 145 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 69 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138268\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85220\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85220\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138268 \u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 85220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e19\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e32\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e31\u0e01\u0e29\u0e30\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e0a\u0e35\u0e1e (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u6559\u80b2 2  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 18 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138276\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138276 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22  \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 2823\/3  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138314\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e2d\u0e0796 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138314 \u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e2d\u0e0796 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c (branding) \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 355  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2796(\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e222) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138349\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e23\u0e31\u0e48\u0e07\u0e41\u0e21\u0e48\u0e01\u0e25\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47741\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47741\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138349 \u0e1a\u0e08.\u0e2b\u0e23\u0e31\u0e48\u0e07\u0e41\u0e21\u0e48\u0e01\u0e25\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47741 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e33 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e21\u0e07\u0e04\u0e25\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 228\/170  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e23\u0e34\u0e04\u0e42\u0e04\u0e49 \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e16\u0e19\u0e19\u0e23\u0e48\u0e27\u0e21\u0e21\u0e34\u0e15\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138357\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90001\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90001\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138357 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 90001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25 \u0e02\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e0a\u0e48\u0e32 \u0e22\u0e37\u0e21 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 29\/63  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138365\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e30\u0e25\u0e32\u0e19\u0e15\u0e32 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138365 \u0e1a\u0e08.\u0e25\u0e30\u0e25\u0e32\u0e19\u0e15\u0e32 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138390\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e2a\u0e15\u0e35\u0e25 \u0e40\u0e21\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138390 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e2a\u0e15\u0e35\u0e25 \u0e40\u0e21\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e15\u0e30\u0e41\u0e01\u0e23\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e09\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/92  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138403\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138403 \u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1b\u0e31\u0e4a\u0e21\u0e40\u0e04\u0e21\u0e35\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 239\/41  \u0e16\u0e19\u0e1901 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138454\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e27\u0e25 \u0e2d\u0e31\u0e1e \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46491\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46491\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138454 \u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e27\u0e25 \u0e2d\u0e31\u0e1e \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31  \u0e0b\u0e2d\u0e22 \u0e09\u0e25\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07 25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138462\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138462 \u0e1a\u0e08.\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 252  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e2d\u0e35 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 tt 10 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e4810 \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138489\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138489 \u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e0b\u0e2d\u0e22 \u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e41\u0e01\u0e49\u0e27 3 \u0e41\u0e22\u0e01 13 \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e41\u0e01\u0e49\u0e27 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024131\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e31\u0e25 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024131 \u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e31\u0e25 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 73102 \u0e07\u0e32\u0e19 tiktok affiliate: \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (digital marketing) \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\\\" \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 280\/145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024157\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e25\u0e01\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024157 \u0e1a\u0e08.\u0e1f\u0e35\u0e25\u0e01\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 999\/148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024165\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e35\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024165 \u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e35\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content creator) \u0e01\u0e32\u0e23\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e01 \u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 78\/191  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024181\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e20\u0e13 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024181 \u0e1a\u0e08.\u0e25\u0e20\u0e13 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/31\u0e01.  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e2d\u0e38\u0e14\u0e21\u0e40\u0e14\u0e0a \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024211\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e25\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024211 \u0e1a\u0e08.\u0e04\u0e39\u0e25\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30 \u0e23\u0e16\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 93\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024238\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e49\u0e21\u0e15\u0e33 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024238 \u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e49\u0e21\u0e15\u0e33 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e49\u0e21\u0e15\u0e33 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 99\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024262\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e34\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024262 \u0e1a\u0e08.\u0e22\u0e34\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 86\/198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024289\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e41\u0e27\u0e19\u0e17\u0e32\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024289 \u0e1a\u0e08.\u0e2d\u0e41\u0e27\u0e19\u0e17\u0e32\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 66191 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 482\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024297\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e15\u0e49\u0e32-\u0e27\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024297 \u0e1a\u0e08.\u0e40\u0e21\u0e15\u0e49\u0e32-\u0e27\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 236\/135  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e4c 83 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024319\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08.\u0e08\u0e2d\u0e22 \u0e27\u0e23\u0e23\u0e13\u0e21\u0e07\u0e04\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024319 \u0e1a\u0e08.\u0e40\u0e08.\u0e08\u0e2d\u0e22 \u0e27\u0e23\u0e23\u0e13\u0e21\u0e07\u0e04\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47190 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 212\/209  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024327\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e08 \u0e21\u0e07\u0e04\u0e25 \u0e17\u0e27\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024327 \u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e08 \u0e21\u0e07\u0e04\u0e25 \u0e17\u0e27\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01 \u0e1b\u0e38\u0e4b\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e21\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 212\/209  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002275\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e21\u0e14\u0e32\u0e23\u0e48\u0e32\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002275 \u0e2b\u0e08.\u0e42\u0e21\u0e14\u0e32\u0e23\u0e48\u0e32 2569-07-22 1000000 47113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e21\u0e34\u0e19\u0e34\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 119\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0123569002283\",\"name_th\":\"\u0e2b\u0e08.\u0e2e\u0e31\u0e01\u0e01\u0e35\u0e49 \u0e17\u0e2d\u0e22\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002283 \u0e2b\u0e08.\u0e2e\u0e31\u0e01\u0e01\u0e35\u0e49 \u0e17\u0e2d\u0e22 2569-07-22 1000000 47640 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e0b\u0e36\u0e48\u0e07 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027555\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e1a\u0e2a\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027555 \u0e1a\u0e08.\u0e1e\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e1a\u0e2a\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 59\/6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e1a\u0e39\u0e40\u0e25\u0e2d\u0e27\u0e32\u0e23\u0e4c\u0e14 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027563\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e33\u0e14\u0e35 \u0e0b\u0e35 \u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027563 \u0e1a\u0e08.\u0e17\u0e33\u0e14\u0e35 \u0e0b\u0e35 \u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 43\/930  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027601\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e25\u0e2a\u0e34\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027601 \u0e1a\u0e08.\u0e0a\u0e25\u0e2a\u0e34\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e39\u0e15\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027610\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027610 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027628\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e04\u0e2d\u0e1f\u0e1f\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96301\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96301\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027628 \u0e1a\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e04\u0e2d\u0e1f\u0e1f\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 96301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e25\u0e07\u0e28\u0e1e \u0e2b\u0e35\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e28\u0e1e \u0e2b\u0e35\u0e1a\u0e2d\u0e31\u0e10\u0e34 \u0e42\u0e01\u0e28 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e1e\u0e27\u0e07\u0e2b\u0e23\u0e35\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e1c\u0e49\u0e32\u0e14\u0e34\u0e1a \u0e1c\u0e49\u0e32\u0e02\u0e32\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e28\u0e1e \u0e07\u0e32\u0e19\u0e0c\u0e32\u0e1b\u0e19\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 18\/58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027644\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e1b\u0e2d\u0e25\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027644 \u0e1a\u0e08.\u0e42\u0e2d\u0e1b\u0e2d\u0e25\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 234\/68  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0b\u0e19\u0e42\u0e17\u0e23 \u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027652\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e21\u0e34 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027652 \u0e1a\u0e08.\u0e21\u0e35\u0e21\u0e34 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e07\u0e21\u0e31\u0e17\u0e09\u0e30\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e19\u0e33\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e02\u0e19\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 152\/331  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e19\u0e0b\u0e35\u0e42\u0e2d \u0e04\u0e23\u0e34\u0e1b \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32 - \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027661\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e20\u0e32\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22\u0e42\u0e25\u0e01 (\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e35) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93192\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93192\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027661 \u0e1a\u0e08.\u0e2a\u0e20\u0e32\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22\u0e42\u0e25\u0e01 (\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e35) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 93192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e0a\u0e01\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e \u0e01\u0e15\u0e34\u0e01\u0e32 \u0e21\u0e32\u0e23\u0e22\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e27\u0e07\u0e01\u0e32\u0e23\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e0a\u0e34\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e41\u0e0a\u0e21\u0e40\u0e1b\u0e35\u0e49\u0e22\u0e19\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e17\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 9  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022588\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46415\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46415\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022588 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46415 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022596\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022596 \u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 16\/11  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1a\u0e25\u0e25\u0e48\u0e32 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e04\u0e25\u0e2d\u0e073 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022600\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e31\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022600 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e31\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e14\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e27\u0e31\u0e15\u0e15\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e33\u0e19\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u91d1\u878d\u30fb\u4fdd\u967a 168\/179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 11 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022618\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e21\u0e34\u0e01\u0e0b\u0e4c\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022618 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e21\u0e34\u0e01\u0e0b\u0e4c\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 79\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022626\",\"name_th\":\"\u0e1a\u0e08.89 \u0e42\u0e21\u0e42\u0e15 \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022626 \u0e1a\u0e08.89 \u0e42\u0e21\u0e42\u0e15 \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022642\",\"name_th\":\"\u0e1a\u0e08.227 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022642 \u0e1a\u0e08.227 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 39\/124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022669\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e48\u0e21\u0e01\u0e21\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022669 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e48\u0e21\u0e01\u0e21\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e1b\u0e35 \u4e0d\u52d5\u7523 39\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022677\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e25\u0e21\u0e2d\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022677 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e25\u0e21\u0e2d\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e17\u0e33\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e14\u0e46 \u0e01\u0e47\u0e15\u0e32\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01\u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e16\u0e32\u0e14\u0e44\u0e02\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 72\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004784\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e07\u0e01\u0e07\u0e27\u0e31\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e14\u0e35\u0e40\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004784 \u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e07\u0e01\u0e07\u0e27\u0e31\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e14\u0e35\u0e40\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e0a\u0e47\u0e04\u0e1b\u0e31\u0e4a\u0e21  \u0e2b\u0e31\u0e27\u0e09\u0e35\u0e14 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 206\/242-243  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004792\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25921\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25921\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004792 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 25921 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0a\u0e38\u0e1a\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1c\u0e34\u0e27\u0e42\u0e25\u0e2b\u0e30\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2a\u0e35 \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 133\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0155569000606\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46439\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46439\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000606 \u0e1a\u0e08.\u0e2a\u0e32\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46439 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e31\u0e01\u0e2a\u0e32\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e08\u0e31\u0e01\u0e2a\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01  \u0e44\u0e21\u0e49 \u0e2b\u0e27\u0e32\u0e22 \u0e44\u0e21\u0e49\u0e44\u0e1c\u0e48 \u0e01\u0e01 \u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0155569000614\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000614 \u0e1a\u0e08.\u0e40\u0e2d\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e15\u0e25\u0e32\u0e14\u0e2a\u0e14 \u0e15\u0e25\u0e32\u0e14\u0e19\u0e31\u0e14 \u0e15\u0e25\u0e32\u0e14\u0e40\u0e1b\u0e34\u0e14\u0e25\u0e17\u0e49\u0e32\u0e22\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e16\u0e19\u0e19\u0e04\u0e19\u0e40\u0e14\u0e34\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 96\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0195569002668\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e17\u0e48\u0e2d\u0e21 \u0e43\u0e1a\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002668 \u0e1a\u0e08.\u0e04\u0e2d\u0e17\u0e48\u0e2d\u0e21 \u0e43\u0e1a\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e41\u0e2b\u0e49\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038297\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038297 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 87\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038301\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e22\u0e39\u0e17\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038301 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e40\u0e04 \u0e22\u0e39\u0e17\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 43223 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u5efa\u8a2d 88\/15  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e39\u0e25\u0e40\u0e21\u0e49\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e48\u0e19\u0e2a\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038319\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e1a\u0e2d\u0e23\u0e4c\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2027 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038319 \u0e1a\u0e08.\u0e23\u0e35\u0e1a\u0e2d\u0e23\u0e4c\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2027 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e14\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u904b\u8f38\u30fb\u7269\u6d41 6\/108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038343\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e0b\u0e35\u0e42\u0e23\u0e48 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038343 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e0b\u0e35\u0e42\u0e23\u0e48 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e04\u0e31\u0e14\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e22\u0e30\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e02\u0e22\u0e30\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e40\u0e02\u0e32\u0e0a\u0e35\u0e0b\u0e2d\u0e222 \u0e16\u0e19\u0e19\u0e40\u0e02\u0e32\u0e0a\u0e35-\u0e22\u0e32\u0e07\u0e40\u0e2d\u0e19 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038378\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e32\u0e07\u0e40\u0e2b\u0e2d \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038378 \u0e1a\u0e08.\u0e09\u0e32\u0e07\u0e40\u0e2b\u0e2d \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 82990 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 198\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038394\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e42\u0e2e\u0e21\u0e1f\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46634\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46634\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038394 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e42\u0e2e\u0e21\u0e1f\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46634 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038416\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35. \u0e40\u0e04. \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038416 \u0e1a\u0e08.\u0e14\u0e35. \u0e40\u0e04. \u0e1e\u0e32\u0e23\u0e32\u0e44\u0e14\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 238\/64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038424\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e40\u0e2d\u0e2a \u0e28\u0e23\u0e35\u0e23\u0e32\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038424 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e40\u0e2d\u0e2a \u0e28\u0e23\u0e35\u0e23\u0e32\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e49\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 (delivery) \u5bbf\u6cca\u30fb\u98f2\u98df 18\/248  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038432\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e27\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038432 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e27\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038467\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e14\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038467 \u0e1a\u0e08.\u0e22\u0e39\u0e14\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 129\/206  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038475\",\"name_th\":\"\u0e1a\u0e08.9 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25113\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25113\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038475 \u0e1a\u0e08.9 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 25113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 26\/1205  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038483\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e35\u0e42\u0e04\u0e48 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038483 \u0e1a\u0e08.\u0e43\u0e2b\u0e21\u0e48 \u0e2d\u0e35\u0e42\u0e04\u0e48 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e19\u0e33\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e28\u0e29\u0e42\u0e25\u0e2b\u0e30 \u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 (recycle) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 10\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038513\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e1f\u0e27\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038513 \u0e1a\u0e08.\u0e40\u0e2e\u0e1f\u0e27\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 93\/55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038521\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e13\u0e27\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038521 \u0e1a\u0e08.\u0e2d\u0e2d\u0e13\u0e27\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46103 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038530\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e42\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038530 \u0e1a\u0e08.\u0e40\u0e27\u0e42\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46103 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038548\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e25\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038548 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e25\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e39\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 130\/127  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001324\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e42\u0e2d\u0e4a\u0e15 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001324 \u0e2b\u0e08.\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e42\u0e2d\u0e4a\u0e15 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 131\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0213569001332\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c.\u0e2d\u0e23\u0e34\u0e2a\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49321\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49321\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001332 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c.\u0e2d\u0e23\u0e34\u0e2a\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-22 1000000 49321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u904b\u8f38\u30fb\u7269\u6d41 25  \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e07\u0e43\u0e19 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e07 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009700\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e31\u0e48\u0e27\u0e44\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009700 \u0e1a\u0e08.\u0e2e\u0e31\u0e48\u0e27\u0e44\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e22\u0e37\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e20\u0e32\u0e29\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 321   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a106 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009718\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e21 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009718 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e21 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28  \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 92\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009726\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009726 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 22299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32-\u0e02\u0e32\u0e22\u0e44\u0e1b\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 33\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009751\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e49\u0e19\u0e08\u0e35\u0e48 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009751 \u0e1a\u0e08.\u0e25\u0e34\u0e49\u0e19\u0e08\u0e35\u0e48 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 81210 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 231\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009769\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e0a\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009769 \u0e1a\u0e08.\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e0a\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47630 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0235569000435\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e2d\u0e32 \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0235569000435 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e2d\u0e32 \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e23\u0e49\u0e2d\u0e19-\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e01\u0e33\u0e2b\u0e19\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0235569000443\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e1e\u0e07\u0e29\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e31\u0e07\u0e40\u0e2d\u0e34\u0e0d  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0235569000443 \u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e1e\u0e07\u0e29\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e31\u0e07\u0e40\u0e2d\u0e34\u0e0d  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 58\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0245569003981\",\"name_th\":\"\u0e1a\u0e08.888 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003981 \u0e1a\u0e08.888 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e44\u0e2e\u0e42\u0e14\u0e23\u0e25\u0e34\u0e01 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 258\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002098\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e19\u0e2e\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e35\u0e22\u0e07\u0e40\u0e22\u0e27\u0e48 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002098 \u0e1a\u0e08.\u0e08\u0e35\u0e19\u0e2e\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e35\u0e22\u0e07\u0e40\u0e22\u0e27\u0e48 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e35\u0e19\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 544  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0265569000826\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21-\u0e42\u0e2e\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000826 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21-\u0e42\u0e2e\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0303569002818\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002818 \u0e2b\u0e08.\u0e1a\u0e35\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25 2569-07-22 1000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 233  \u0e16\u0e19\u0e19\u0e2d\u0e31\u0e29\u0e0e\u0e32\u0e07\u0e04\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002842\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e19\u0e20\u0e31\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e44\u0e1e\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002842 \u0e2b\u0e08.\u0e1e\u0e23\u0e19\u0e20\u0e31\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e44\u0e1e\u0e23\u0e4c\u0e21 2569-07-22 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 66\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002851\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e1b\u0e25\u0e32\u0e2a\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002851 \u0e2b\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e1b\u0e25\u0e32\u0e2a\u0e14 2569-07-22 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e2a\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 252\/4  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e17\u0e48\u0e32\u0e15\u0e30\u0e42\u0e01 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002869\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e1924\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002869 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e1924 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 76\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002877\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e32 \u0e23\u0e32\u0e1f\u0e17\u0e4c\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002877 \u0e2b\u0e08.\u0e14\u0e32 \u0e23\u0e32\u0e1f\u0e17\u0e4c 2569-07-22 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1225  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e0b\u0e2d\u0e22 \u0e21\u0e35\u0e42\u0e0a\u0e042 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e04\u0e42\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007561 \u0e1a\u0e08.\u0e40\u0e17\u0e04\u0e42\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 398  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007579\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e32\u0e01\u0e31\u0e27\u0e23\u0e4c \u0e17\u0e23\u0e31\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007579 \u0e1a\u0e08.\u0e08\u0e32\u0e01\u0e31\u0e27\u0e23\u0e4c \u0e17\u0e23\u0e31\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007587\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e38\u0e4b\u0e22\u0e41\u0e21\u0e48\u0e42\u0e08\u0e49\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23(\u0e41\u0e2a\u0e07\u0e2a\u0e32\u0e22\u0e17\u0e2d\u0e07) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007587 \u0e1a\u0e08.\u0e1b\u0e38\u0e4b\u0e22\u0e41\u0e21\u0e48\u0e42\u0e08\u0e49\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23(\u0e41\u0e2a\u0e07\u0e2a\u0e32\u0e22\u0e17\u0e2d\u0e07) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 555\/12  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e40\u0e2e\u0e49\u0e32\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007609\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13\u0e19\u0e32\u0e22\u0e19\u0e34\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007609 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13\u0e19\u0e32\u0e22\u0e19\u0e34\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01  \u0e25\u0e32\u0e19\u0e01\u0e32\u0e07\u0e40\u0e15\u0e49\u0e19\u0e17\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001111\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1b\u0e23\u0e34\u0e49\u0e19\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001111 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1b\u0e23\u0e34\u0e49\u0e19 2569-07-22 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0355569000418\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e17\u0e35.\u0e1e\u0e35.999\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0355569000418 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e17\u0e35.\u0e1e\u0e35.999\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 206  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e44\u0e27 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003252\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35.\u0e17\u0e35 \u0e2a\u0e41\u0e1b\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e17 1988\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003252 \u0e2b\u0e08.\u0e17\u0e35.\u0e17\u0e35 \u0e2a\u0e41\u0e1b\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e17 1988 2569-07-22 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u88fd\u9020 60\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003261\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e32888\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003261 \u0e2b\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e32888 2569-07-22 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e49\u0e32\u0e27 \u0e19\u0e49\u0e33 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e02\u0e19\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e1e\u0e47\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 423\/180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003279\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003279 \u0e2b\u0e08.\u0e04\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 2569-07-22 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e04\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e01\u0e29\u0e30\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e40\u0e14\u0e47\u0e01 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u6559\u80b2 1001\/10  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35 \u0e2a\u0e40\u0e1b\u0e0b \u0e42\u0e19\u0e19\u0e21\u0e48\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003287\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e41\u0e04\u0e2a\u0e41\u0e04\u0e21\u0e1b\u0e4c\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003287 \u0e2b\u0e08.\u0e17\u0e35\u0e41\u0e04\u0e2a\u0e41\u0e04\u0e21\u0e1b\u0e4c 2569-07-22 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e48\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e04\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e01\u0e29\u0e30\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e40\u0e14\u0e47\u0e01 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u6559\u80b2 1001\/10  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35 \u0e2a\u0e40\u0e1b\u0e0b \u0e42\u0e19\u0e19\u0e21\u0e48\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007012\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e27\u0e35\u0e48 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007012 \u0e1a\u0e08.\u0e44\u0e2d\u0e27\u0e35\u0e48 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 76  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e42\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007039\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e2a \u0e23\u0e27\u0e22\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007039 \u0e1a\u0e08.\u0e1e\u0e32\u0e2a \u0e23\u0e27\u0e22\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 634\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007047\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e42\u0e2e\u0e212026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007047 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e42\u0e2e\u0e212026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e17\u0e22\u0e17\u0e38\u0e01\u0e04\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007055\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2517 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007055 \u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2517 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 20121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u88fd\u9020 182  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007063\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e25\u0e32\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007063 \u0e1a\u0e08.\u0e2a\u0e38\u0e25\u0e32\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 286  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001705\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e27\u0e34\u0e19 \u0e40\u0e27\u0e25\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001705 \u0e2b\u0e08.\u0e21\u0e32\u0e27\u0e34\u0e19 \u0e40\u0e27\u0e25 2569-07-22 1000000 46599 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2a\u0e27\u0e34\u0e15\u0e0a\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0a\u0e19\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e25\u0e30\u0e08\u0e48\u0e32\u0e22\u0e44\u0e1f \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (closed-circuittelevision \u0e2b\u0e23\u0e37\u0e2d cctv) \u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e34\u0e19\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1c\u0e08\u0e0d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e23\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e40\u0e0a\u0e48\u0e19 \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 217  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003874\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003874 \u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07 \u0e02\u0e19\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 206\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0433569000458\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e28\u0e21\u0e35 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e41\u0e17\u0e49\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"15129\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"15129\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000458 \u0e2b\u0e08.\u0e23\u0e31\u0e28\u0e21\u0e35 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e41\u0e17\u0e49 2569-07-22 1000000 15129 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e41\u0e17\u0e49 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e41\u0e17\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 42  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0435569001154\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e35\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001154 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e35\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 313  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0435569001162\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e14\u0e25 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001162 \u0e1a\u0e08.\u0e13\u0e14\u0e25 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0445569001766\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2a\u0e35\u0e17\u0e2d\u0e07 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001766 \u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2a\u0e35\u0e17\u0e2d\u0e07 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 43301 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u5efa\u8a2d 9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0493569000415\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e08\u0e1e\u0e35 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0493569000415 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e08\u0e1e\u0e35 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 88\/26  \u0e16\u0e19\u0e19\u0e15\u0e32\u0e14\u0e41\u0e04\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0495569000557\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35\u0e40\u0e2d\u0e0a\u0e0b\u0e35 \u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000557 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35\u0e40\u0e2d\u0e0a\u0e0b\u0e35 \u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e15\u0e34\u0e14\u0e40\u0e15\u0e35\u0e22\u0e07  \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u533b\u7642\u30fb\u798f\u7949 22  \u0e0b\u0e2d\u0e22 \u0e15\u0e32\u0e14\u0e41\u0e04\u0e1913 \u0e16\u0e19\u0e19\u0e15\u0e32\u0e14\u0e41\u0e04\u0e19 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0495569000565\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e0a\u0e0a\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000565 \u0e1a\u0e08.\u0e1e\u0e34\u0e0a\u0e0a\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/4  \u0e16\u0e19\u0e19\u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e0a\u0e32\u0e22\u0e42\u0e02\u0e07\u0e43\u0e15\u0e49 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005122\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e25\u0e21\u0e40\u0e1a\u0e23\u0e15\u0e15\u0e49\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005122 \u0e2b\u0e08.\u0e41\u0e25\u0e21\u0e40\u0e1a\u0e23\u0e15\u0e15\u0e49\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 160\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016509\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04 \u0e1e\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016509 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04 \u0e1e\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e02\u0e49\u0e32\u0e1e\u0e33\u0e19\u0e31\u0e01\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07 \u0e14\u0e49\u0e32\u0e19\u0e08\u0e2d\u0e07\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e27\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 185  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016517\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e31\u0e19\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016517 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e31\u0e19\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0533569000538\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e32\u0e0a\u0e31\u0e19\u0e22\u0e4c\u0e04\u0e49\u0e32\u0e44\u0e21\u0e49\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0533569000538 \u0e2b\u0e08.\u0e23\u0e32\u0e0a\u0e31\u0e19\u0e22\u0e4c\u0e04\u0e49\u0e32\u0e44\u0e21\u0e49 2569-07-22 1000000 46632 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e49\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e44\u0e2a\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e44\u0e21\u0e49 \u0e42\u0e23\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 136  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0535569000815\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e35 \u0e44\u0e0b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000815 \u0e1a\u0e08.\u0e0a\u0e35 \u0e44\u0e0b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 52292 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07 (\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23) \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04  \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0563569000635\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e31\u0e27\u0e40\u0e2e\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0563569000635 \u0e2b\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e31\u0e27\u0e40\u0e2e\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-22 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 270  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0575569004721\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004721 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e40\u0e2b\u0e15\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23-\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004730\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e27\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004730 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e27\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 31001 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 217  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 26 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004748\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e27\u0e34\u0e19\u0e17\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004748 \u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e27\u0e34\u0e19\u0e17\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47591 \u0e02\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e07\u0e32\u0e19\u0e44\u0e21\u0e49 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e42\u0e15\u0e4a\u0e30 \u0e15\u0e39\u0e49\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e15\u0e35\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004756\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e23\u0e21\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004756 \u0e1a\u0e08.\u0e40\u0e1b\u0e23\u0e21\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 130\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e40\u0e14\u0e48\u0e19\u0e2b\u0e49\u0e32-\u0e14\u0e07\u0e21\u0e30\u0e14\u0e30 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004772\",\"name_th\":\"\u0e1a\u0e08.\u0e13 \u0e08\u0e38 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004772 \u0e1a\u0e08.\u0e13 \u0e08\u0e38 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004781\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c  \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004781 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c  \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e2a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 299\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004799\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e0a\u0e31\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e21\u0e0b\u0e39 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004799 \u0e1a\u0e08.\u0e21\u0e35\u0e0a\u0e31\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e21\u0e0b\u0e39 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2b\u0e2d\u0e21\u0e2b\u0e31\u0e27\u0e43\u0e2b\u0e0d\u0e48 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e1e\u0e23\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001673\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35\u0e14\u0e35\u0e1a\u0e35\u0e1a\u0e35\u0e04\u0e23\u0e35\u0e21\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001673 \u0e2b\u0e08.\u0e14\u0e35\u0e14\u0e35\u0e1a\u0e35\u0e1a\u0e35\u0e04\u0e23\u0e35\u0e21 2569-07-22 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0645569000768\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e2a\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000768 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e2a\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47912 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102\/9  \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e07\u0e2b\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0655569002345\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e42\u0e0a\u0e04 \u0e1e\u0e25\u0e31\u0e2a1 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002345 \u0e1a\u0e08.\u0e18\u0e19\u0e42\u0e0a\u0e04 \u0e1e\u0e25\u0e31\u0e2a1 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 facebook, google,tiktok \u0e41\u0e25\u0e30youtube, instagram \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 210  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002353\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e1e\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002353 \u0e1a\u0e08.\u0e17\u0e39\u0e1e\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0675569001543\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e14\u0e35 99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001543 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e14\u0e35 99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0703569000501\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e20\u0e31\u0e17\u0e23\u0e4c 289\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0703569000501 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e20\u0e31\u0e17\u0e23\u0e4c 289 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002743\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e0a\u0e32\u0e28\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002743 \u0e1a\u0e08.\u0e2d\u0e0a\u0e32\u0e28\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002751\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e2a\u0e21\u0e38\u0e17\u0e23 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002751 \u0e1a\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e2a\u0e21\u0e38\u0e17\u0e23 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c (\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e22\u0e32\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002182\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e22\u0e30\u0e04\u0e35\u0e23\u0e35 333 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002182 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e22\u0e30\u0e04\u0e35\u0e23\u0e35 333 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 289  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001117\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1f\u0e23\u0e35\u0e48 \u0e44\u0e17\u0e21\u0e4c \u0e1f\u0e39\u0e14\u0e2a\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e23\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001117 \u0e2b\u0e08.\u0e40\u0e2d\u0e1f\u0e23\u0e35\u0e48 \u0e44\u0e17\u0e21\u0e4c \u0e1f\u0e39\u0e14\u0e2a\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e23\u0e34\u0e49\u0e07 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 14\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0733569001125\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1a\u0e19\u0e22\u0e32\u0e21\u0e34\u0e19 2023\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001125 \u0e2b\u0e08.\u0e40\u0e1a\u0e19\u0e22\u0e32\u0e21\u0e34\u0e19 2023 2569-07-22 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 61\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007401\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e4a\u0e14\u0e40\u0e14\u0e25\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01630\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01630\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007401 \u0e1a\u0e08.\u0e2d\u0e35\u0e4a\u0e14\u0e40\u0e14\u0e25\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 01630 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u8fb2\u6797\u6c34\u7523 137  \u0e16\u0e19\u0e19\u0e17\u0e27\u0e32\u0e23\u0e32\u0e27\u0e14\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007419\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e29\u0e23\u0e32 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007419 \u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e29\u0e23\u0e32 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47722 \u0e1b\u0e23\u0e30\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e1a \u0e2a\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e01\u0e49\u0e32\u0e19\u0e44\u0e21\u0e49\u0e2b\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e47\u0e2d\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e01\u0e25\u0e34\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32\u0e40\u0e17\u0e2d\u0e23\u0e32\u0e1e\u0e35 \u0e15\u0e25\u0e2d\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007427\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e0a\u0e23\u0e35 \u0e42\u0e20\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e21\u0e39\u0e2a\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007427 \u0e1a\u0e08.\u0e1e\u0e31\u0e0a\u0e23\u0e35 \u0e42\u0e20\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e21\u0e39\u0e2a\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e01\u0e23\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e01\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e01\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e2a\u0e38\u0e01\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 241\/1   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e41\u0e1c\u0e07 f6 \u0e16\u0e19\u0e19\u0e17\u0e27\u0e32\u0e23\u0e32\u0e27\u0e14\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007711\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e23\u0e32\u0e42\u0e01\u0e23\u0e27\u0e4c \u0e41\u0e04\u0e19\u0e19\u0e32\u0e1a\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007711 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e23\u0e32\u0e42\u0e01\u0e23\u0e27\u0e4c \u0e41\u0e04\u0e19\u0e19\u0e32\u0e1a\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e1b\u0e25\u0e39\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e31\u0e0d\u0e0a\u0e07\u0e41\u0e25\u0e30\u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u8fb2\u6797\u6c34\u7523 3\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007745\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0a\u0e21\u0e1b\u0e4c\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007745 \u0e1a\u0e08.\u0e41\u0e0a\u0e21\u0e1b\u0e4c\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e43\u0e19\u0e17\u0e38\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c  \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007761\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007761 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007770\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 2022 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007770 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 2022 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007788\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e38\u0e48\u0e19\u0e15\u0e31\u0e48\u0e27 \u0e41\u0e21\u0e0a\u0e0a\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007788 \u0e1a\u0e08.\u0e22\u0e38\u0e48\u0e19\u0e15\u0e31\u0e48\u0e27 \u0e41\u0e21\u0e0a\u0e0a\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38\/84,85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0755569000546\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0755569000546 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e2d \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e1c\u0e48\u0e2d\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0775569003081\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e1f\u0e23\u0e21\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003081 \u0e1a\u0e08.\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e1f\u0e23\u0e21\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002858\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e4c\u0e27\u0e32\u0e1e\u0e23\u0e23\u0e13 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002858 \u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e4c\u0e27\u0e32\u0e1e\u0e23\u0e23\u0e13 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e34\u0e27\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07  \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013531\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e17\u0e35.\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013531 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e17\u0e35.\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 141\/51  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010699\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e21\u0e31\u0e19\u0e15\u0e32 \u0e25\u0e32\u0e22\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010699 \u0e1a\u0e08.\u0e2d\u0e21\u0e31\u0e19\u0e15\u0e32 \u0e25\u0e32\u0e22\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010702\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e27\u0e34\u0e0a\u0e31\u0e22\u0e27\u0e07\u0e28\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"02200\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"02200\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010702 \u0e1a\u0e08.\u0e1e\u0e25\u0e27\u0e34\u0e0a\u0e31\u0e22\u0e27\u0e07\u0e28\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 02200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e27\u0e19\u0e1b\u0e48\u0e32 \u8fb2\u6797\u6c34\u7523 440\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010729\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e2a \u0e2d\u0e35\u0e40\u0e14\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010729 \u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e2a \u0e2d\u0e35\u0e40\u0e14\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 72\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010737\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e14\u0e14\u0e34\u0e15\u0e31\u0e2a 77 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010737 \u0e1a\u0e08.\u0e40\u0e23\u0e14\u0e14\u0e34\u0e15\u0e31\u0e2a 77 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 165\/278  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010745\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010745 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 165\/277  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010753\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c \u0e2a\u0e21\u0e38\u0e22 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010753 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c \u0e2a\u0e21\u0e38\u0e22 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 131\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0855569000553\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e2a\u0e40\u0e1b\u0e0b \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000553 \u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e2a\u0e40\u0e1b\u0e0b \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 371  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001274\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001274 \u0e1a\u0e08.\u0e0b\u0e35\u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569005996\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005996 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46695 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 \u0e40\u0e28\u0e29\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e21\u0e39\u0e25\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30 \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 229  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006011\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e47\u0e01\u0e0b\u0e2d\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006011 \u0e1a\u0e08.\u0e40\u0e23\u0e47\u0e01\u0e0b\u0e2d\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32  \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 243  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e02\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006020\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e04\u0e34\u0e27\u0e40\u0e23\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006020 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e04\u0e34\u0e27\u0e40\u0e23\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 141\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006038\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e19\u0e38\u0e01 66  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006038 \u0e1a\u0e08.\u0e2a\u0e19\u0e38\u0e01 66  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 394\/1  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e19\u0e34\u0e0a \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006046\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e08\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006046 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e08\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006054\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006054 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e2d\u0e37\u0e48\u0e19 \u0e46   \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 70  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e0b\u0e2d\u0e22 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006062\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e20\u0e28\u0e34\u0e29\u0e0f\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006062 \u0e1a\u0e08.\u0e18\u0e19\u0e20\u0e28\u0e34\u0e29\u0e0f\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001117\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001117 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 38\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0935569000862\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e40\u0e17\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000862 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e40\u0e17\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e14\u0e22\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 427\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0103569007862\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e27\u0e25\u0e35\u0e48\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007862 \u0e2b\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e27\u0e25\u0e35\u0e48 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 279\/3  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007871\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e19\u0e38\u0e0a\u0e32 69\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007871 \u0e2b\u0e08.\u0e2d\u0e19\u0e38\u0e0a\u0e32 69 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 534  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 44 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136818\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e32\u0e08\u0e38\u0e4a\u0e1a\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136818 \u0e1a\u0e08.\u0e15\u0e32\u0e08\u0e38\u0e4a\u0e1a\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 929\/4  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136826\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136826 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 165\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e17\u0e1e\u0e18\u0e32\u0e19\u0e35 \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e23.\u0e59\u0e0b.62\u0e41\u0e22\u0e016 \u0e16\u0e19\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136834\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e23\u0e39\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136834 \u0e1a\u0e08.\u0e1f\u0e23\u0e39\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (oem) \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 331  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136842\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e01\u0e34\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136842 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e01\u0e34\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 70209 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01 \u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14 \u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28  (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 749 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136869\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c.\u0e40\u0e21\u0e17\u0e17\u0e31\u0e25\u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45404\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45404\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136869 \u0e1a\u0e08.\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c.\u0e40\u0e21\u0e17\u0e17\u0e31\u0e25\u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45404 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 311\/46  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c35\/1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136940\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e14\u0e47\u0e2d\u0e04 \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136940 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e14\u0e47\u0e2d\u0e04 \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e41\u0e1c\u0e48\u0e19 \u0e41\u0e16\u0e1a\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e44\u0e1f\u0e25\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u82b8\u8853\u30fb\u5a2f\u697d 236\/81  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 68 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136958\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e1b\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136958 \u0e1a\u0e08.\u0e0b\u0e34\u0e1b\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/318  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04 38 \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 25 \u0e41\u0e22\u0e01 8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136966\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e34\u0e15\u0e49\u0e32 \u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136966 \u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e34\u0e15\u0e49\u0e32 \u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 64201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e21\u0e48 (holding company) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14  \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 157\/70  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e39\u0e19\u0e2a\u0e34\u0e19\u0e18\u0e32\u0e19\u0e35 1 \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 64 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136974\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e04\u0e23\u0e47\u0e2d\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136974 \u0e1a\u0e08.\u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e04\u0e23\u0e47\u0e2d\u0e01 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e14\u0e34\u0e1a \u0e1c\u0e49\u0e32\u0e41\u0e1e\u0e23 \u0e1c\u0e49\u0e32\u0e1d\u0e49\u0e32\u0e22 \u0e1c\u0e49\u0e32\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22 \u0e44\u0e2b\u0e21 \u0e43\u0e22\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e22\u0e47\u0e1a\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e48\u0e19\u0e14\u0e49\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e14\u0e49\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07  \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e2d\u0e22\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3388\/25-37  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 8-11 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 \u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136982\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e27\u0e31\u0e0a\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136982 \u0e1a\u0e08.\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e27\u0e31\u0e0a\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e04\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 24\u0e41\u0e22\u0e0134(\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e01\u0e30\u0e08\u0e30) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136991\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136991 \u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e0a\u0e48\u0e27\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e16\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61\/11-12,61\/180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137041\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e27 \u0e17\u0e48\u0e32\u0e1e\u0e23\u0e30\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137041 \u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e27 \u0e17\u0e48\u0e32\u0e1e\u0e23\u0e30\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21\u0e2d\u0e1a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 75,77  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137067\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e39\u0e49\u0e14\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2a\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137067 \u0e1a\u0e08.\u0e27\u0e39\u0e49\u0e14\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2a\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 22  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137075\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e2d\u0e25\u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137075 \u0e1a\u0e08.\u0e27\u0e2d\u0e25\u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e34\u0e14\u0e41\u0e2d\u0e23\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d (cleanroom) \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 112  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e193\u0e0b\u0e2d\u0e2212 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137083\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137083 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e43\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 899\/19  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137113\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e2b\u0e25\u0e35\u0e22\u0e07 \u0e0a\u0e4a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137113 \u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e2b\u0e25\u0e35\u0e22\u0e07 \u0e0a\u0e4a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e22\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e32\u0e22\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2a\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e2a\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2a\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c                   \u0e2a\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07 \u0e2a\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e21\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e44\u0e21\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 75\/279  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 unio town \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 76 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 76 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137121\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e17\u0e17\u0e4c \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137121 \u0e1a\u0e08.\u0e1e\u0e34\u0e17\u0e17\u0e4c \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 36 \u0e19\u0e34\u0e04\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e32\u0e07\u0e0a\u0e31\u0e19  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 87 \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137130\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35 \u0e21\u0e34\u0e25\u0e04\u0e4c 159 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10501\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10501\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137130 \u0e1a\u0e08.\u0e08\u0e35 \u0e21\u0e34\u0e25\u0e04\u0e4c 159 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 10501 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e19\u0e21\u0e2a\u0e14 \u0e19\u0e21\u0e1e\u0e32\u0e2a\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e2a\u0e4c \u0e19\u0e21\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e08\u0e32\u0e01\u0e19\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e19\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 40\/5  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e17\u0e1e\u0e19\u0e04\u0e239 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 52 \u0e41\u0e22\u0e01 44 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137148\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0b\u0e32\u0e19\u0e15\u0e49\u0e32 \u0e40\u0e08\u0e41\u0e1b\u0e19 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137148 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0b\u0e32\u0e19\u0e15\u0e49\u0e32 \u0e40\u0e08\u0e41\u0e1b\u0e19 \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 2823\/3   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 314 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137181\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e1a\u0e35\u0e17\u0e35 \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137181 \u0e1a\u0e08.\u0e0b\u0e35\u0e1a\u0e35\u0e17\u0e35 \u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/258  \u0e0b\u0e2d\u0e22 \u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137199\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f\u0e44\u0e14\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137199 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f\u0e44\u0e14\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 122\/56  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 2 \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 36 \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137211\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e2a\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137211 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e2a\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 7\/211  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 127 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137229\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137229 \u0e1a\u0e08.\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 69100 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e31\u0e1a\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e08\u0e33\u0e19\u0e33 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e16\u0e48\u0e16\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 853  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 43 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137237\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e27\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137237 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e27\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2a\u0e16\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u533b\u7642\u30fb\u798f\u7949 135\/2  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e27\u0e32\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137245\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e0b\u0e48\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137245 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e0b\u0e48\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 135\/6  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e27\u0e32\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137253\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e40\u0e2d\u0e32\u0e15\u0e4c\u0e1f\u0e34\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137253 \u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e40\u0e2d\u0e32\u0e15\u0e4c\u0e1f\u0e34\u0e15\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51\/538  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137270\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e27\u0e31\u0e19 \u0e2a\u0e2d\u0e07\u0e04\u0e37\u0e19 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 ) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137270 \u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e27\u0e31\u0e19 \u0e2a\u0e2d\u0e07\u0e04\u0e37\u0e19 (\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 ) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e49\u0e01 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e44\u0e27\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e48\u0e07\u0e42\u0e15\u0e4a\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 102\/5  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137288\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e29\u0e21\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86102\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86102\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137288 \u0e1a\u0e08.\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e29\u0e21\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 86102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e15\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e15\u0e31\u0e14\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e15\u0e32 \u533b\u7642\u30fb\u798f\u7949 18  \u0e0b\u0e2d\u0e22 \u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35  2\/1 \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137300\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e42\u0e23\u0e40\u0e27\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137300 \u0e1a\u0e08.\u0e41\u0e2d\u0e42\u0e23\u0e40\u0e27\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46530 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e16\u0e44\u0e16 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e27\u0e48\u0e32\u0e19 \u0e1b\u0e38\u0e49\u0e22\u0e04\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e27\u0e48\u0e32\u0e19\u0e40\u0e21\u0e25\u0e47\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e32\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e27\u0e14\u0e02\u0e49\u0e32\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e35\u0e14\u0e19\u0e21\u0e27\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e1c\u0e36\u0e49\u0e07 \u0e23\u0e16\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e01\u0e23\u0e21\u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e14\u0e23\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 dji \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 311\/375  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e34\u0e14\u0e23\u0e32\u0e0a\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137334\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e42\u0e2d \u0e40\u0e2d\u0e27\u0e35  \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137334 \u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e42\u0e2d \u0e40\u0e2d\u0e27\u0e35  \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 73101 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e22\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 69  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e31\u0e12\u0e19\u0e322 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137342\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137342 \u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e17\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e17\u0e31\u0e14 \u0e04\u0e2d\u0e23\u0e4c\u0e17  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 106 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 50 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137351\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137351 \u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22 \u0e41\u0e1c\u0e48\u0e19\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e1c\u0e48\u0e19\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e41\u0e2a\u0e07 \u0e2a\u0e35\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e41\u0e1c\u0e48\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e16 \u0e41\u0e1c\u0e48\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1c\u0e48\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e16 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/32  \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137369\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e14\u0e31\u0e01\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137369 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e14\u0e31\u0e01\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 581\/148  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137407\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137407 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e08\u0e49\u0e07\u0e2d\u0e2d\u0e01-\u0e41\u0e08\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32 (\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07) \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e07\u0e32\u0e19 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e07\u0e32\u0e19 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e41\u0e01\u0e49\u0e44\u0e02\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 4 \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27 90 \u0e27\u0e31\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 42\/23   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e25\u0e47\u0e2d\u0e04 b021 \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137415\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e40\u0e2e\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137415 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e40\u0e2e\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e19\u0e27\u0e14 \u0e01\u0e14\u0e08\u0e38\u0e14 \u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27 \u0e40\u0e17\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 (\u0e19\u0e27\u0e14\u0e2a\u0e1b\u0e32) \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 (\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32) \u0e04\u0e23\u0e35\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 67  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137423\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137423 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 125\/1  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 42 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137431\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e0b\u0e35 \u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137431 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e0b\u0e35 \u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5efa\u8a2d 353\/373  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04 7\/1 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e34\u0e14\u0e23\u0e32\u0e0a\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137440\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e23 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137440 \u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e23 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e4a\u0e32\u0e0b\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e27\u0e35 \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e2d\u0e25\u0e1e\u0e35\u0e08\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 124 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137474\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e25\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137474 \u0e1a\u0e08.\u0e40\u0e1a\u0e25\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 199\/711  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e219 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137491\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e25\u0e13\u0e20\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137491 \u0e1a\u0e08.\u0e14\u0e25\u0e13\u0e20\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e49\u0e01 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e44\u0e27\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e01\u0e47\u0e15\u0e32\u0e21\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e48\u0e07\u0e42\u0e15\u0e4a\u0e30 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e40\u0e04\u0e32\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e39\u0e18 \u5bbf\u6cca\u30fb\u98f2\u98df 8  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137512\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e17\u0e35 \u0e21\u0e32\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137512 \u0e1a\u0e08.\u0e2d\u0e35\u0e17\u0e35 \u0e21\u0e32\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 11043 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e1c\u0e07\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u88fd\u9020 1\/178  \u0e0b\u0e2d\u0e22 \u0e28\u0e32\u0e25\u0e32\u0e41\u0e14\u0e07 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137539\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137539 \u0e1a\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 77109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e19\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137547\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35 \u0e1f\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e01\u0e23\u0e35\u0e40\u0e14\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137547 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35 \u0e1f\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e01\u0e23\u0e35\u0e40\u0e14\u0e35\u0e22\u0e19\u0e17\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46691 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e41\u0e15\u0e48\u0e07\u0e01\u0e25\u0e34\u0e48\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e41\u0e15\u0e48\u0e07\u0e23\u0e2a \u0e2a\u0e35\u0e1c\u0e2a\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e08\u0e37\u0e2d\u0e1b\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/108  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 35 (\u0e1e\u0e49\u0e2d\u0e21\u0e2d\u0e34\u0e48\u0e21) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137555\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e0b\u0e38\u0e48\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137555 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e0b\u0e38\u0e48\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 188-190  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e32\u0e44\u0e0a\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137563\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137563 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 885\/326  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1f\u0e2a28  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 885\/326 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1f\u0e2a28 \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e -\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e- \u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137580\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e27\u0e23\u0e4c\u0e40\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137580 \u0e1a\u0e08.\u0e41\u0e27\u0e23\u0e4c\u0e40\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 32111 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 (\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\/\u0e1b\u0e25\u0e35\u0e01) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32 \u88fd\u9020 198\/8  \u0e0b\u0e2d\u0e22 \u0e22\u0e28\u0e40\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137601\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e01\u0e25\u0e27\u0e4c \u0e2d\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137601 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e01\u0e25\u0e27\u0e4c \u0e2d\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e2b\u0e19\u0e31\u0e07\u0e28\u0e35\u0e23\u0e29\u0e30 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e0a\u0e21\u0e1e\u0e39\u0e41\u0e2b\u0e49\u0e07 \u0e41\u0e1c\u0e48\u0e19\u0e40\u0e0a\u0e47\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 (dry shampoo wipe)  \u0e1c\u0e49\u0e32\u0e40\u0e1b\u0e35\u0e22\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 128\/150  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 65 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137610\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e17\u0e18\u0e34\u0e19\u0e35 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46412\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46412\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137610 \u0e1a\u0e08.\u0e40\u0e0b\u0e17\u0e18\u0e34\u0e19\u0e35 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46412 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1788  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3001-3003,3009-3014 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137644\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e01\u0e38\u0e42\u0e2d\u0e01\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137644 \u0e1a\u0e08.\u0e21\u0e34\u0e01\u0e38\u0e42\u0e2d\u0e01\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e19  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 776\/31  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137661\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e08\u0e35\u0e41\u0e2d\u0e25 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137661 \u0e1a\u0e08.\u0e1a\u0e35\u0e08\u0e35\u0e41\u0e2d\u0e25 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 487  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2a\u0e32\u0e22 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137679\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137679 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 487  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e2a\u0e32\u0e22 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024025\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024025 \u0e1a\u0e08.\u0e21\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content creator) \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e1e \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (social media) \u0e41\u0e25\u0e30\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/291  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e2d\u0e30\u0e04\u0e32\u0e40\u0e14\u0e35\u0e22 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024033\",\"name_th\":\"\u0e1a\u0e08.5 \u0e14\u0e48\u0e32\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024033 \u0e1a\u0e08.5 \u0e14\u0e48\u0e32\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024041\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e0a \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 4289  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024041 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e0a \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 4289  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56302 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 29\/52-53  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 66 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024050\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024050 \u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e04\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e49\u0e32\u0e19\u0e44\u0e21\u0e49\u0e2b\u0e2d\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 306\/114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024068\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e19\u0e17\u0e47\u0e2d\u0e1b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024068 \u0e1a\u0e08.\u0e41\u0e2e\u0e19\u0e17\u0e47\u0e2d\u0e1b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 444\/39  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e40\u0e1b\u0e0b  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 vo-009 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024084\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e01\u0e48\u0e17\u0e2d\u0e07\u0e22\u0e49\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024084 \u0e1a\u0e08.\u0e44\u0e01\u0e48\u0e17\u0e2d\u0e07\u0e22\u0e49\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 98\/96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024092\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2d\u0e34\u0e19\u0e1f\u0e32\u0e2a\u0e15\u0e23\u0e31\u0e01\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024092 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2d\u0e34\u0e19\u0e1f\u0e32\u0e2a\u0e15\u0e23\u0e31\u0e01\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e33\u0e01\u0e31\u0e1a \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u91d1\u878d\u30fb\u4fdd\u967a 78\/984   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 103 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024114\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024114 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 78\/235  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002241\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e08\u0e35 \u0e04\u0e39\u0e42\u0e2d\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002241 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e08\u0e35 \u0e04\u0e39\u0e42\u0e2d\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19 2569-07-21 1000000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21,\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 127\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027440\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e34\u0e0d \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027440 \u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e34\u0e0d \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027466\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027466 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e14\u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e14\u0e38\u0e01 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027491\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027491 \u0e1a\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e07\u0e29\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46695 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e15\u0e30\u0e01\u0e31\u0e48\u0e27 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e01\u0e49\u0e27 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027504\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e27\u0e25\u0e15\u0e32 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027504 \u0e1a\u0e08.\u0e19\u0e27\u0e25\u0e15\u0e32 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e27\u0e0a\u0e20\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32 \u0e22\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 217\/90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027512\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22\u0e07\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027512 \u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e07\u0e48\u0e32\u0e22\u0e07\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/323  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027539\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e34\u0e17\u0e17\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027539 \u0e1a\u0e08.\u0e2a\u0e21\u0e34\u0e17\u0e17\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47912 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027547\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23. \u0e1e\u0e34\u0e25\u0e42\u0e25\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46412\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46412\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027547 \u0e1a\u0e08.\u0e14\u0e23. \u0e1e\u0e34\u0e25\u0e42\u0e25\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46412 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002585\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e1f\u0e34\u0e15\u0e2d\u0e34\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002585 \u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e1f\u0e34\u0e15\u0e2d\u0e34\u0e19 2569-07-21 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10  \u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/244  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022421\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022421 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47413 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022448\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e40\u0e01\u0e49\u0e32\u0e40\u0e01\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022448 \u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e40\u0e01\u0e49\u0e32\u0e40\u0e01\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07). \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148\/90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022456\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e27\u0e39\u0e4a\u0e14 \u0e1f\u0e25\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022456 \u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e27\u0e39\u0e4a\u0e14 \u0e1f\u0e25\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07 \u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e22\u0e32\u0e07\u0e25\u0e32\u0e22\u0e44\u0e21\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/850  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022481\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e35\u0e23\u0e4c\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022481 \u0e1a\u0e08.\u0e18\u0e35\u0e23\u0e4c\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 80\/244  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022502\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e40\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022502 \u0e1a\u0e08.\u0e14\u0e32\u0e40\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 126\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022511\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e21 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022511 \u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e21 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e27\u0e07\u0e16\u0e32\u0e21\u0e2b\u0e19\u0e35\u0e49 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2\/150  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022529\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e19\u0e19\u0e17\u0e4c \u0e22\u0e38\u0e42\u0e23\u0e1b\u0e04\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022529 \u0e1a\u0e08.\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e19\u0e19\u0e17\u0e4c \u0e22\u0e38\u0e42\u0e23\u0e1b\u0e04\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45201 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022537\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e14\u0e352025 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022537 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e14\u0e352025 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 37\/2791  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004741\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f \u0e1a\u0e35 \u0e44\u0e2d\u0e23\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004741 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f \u0e1a\u0e35 \u0e44\u0e2d\u0e23\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 43\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0155569000592\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000592 \u0e1a\u0e08.\u0e04\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e2a\u0e23\u0e49\u0e2d\u0e22\u0e04\u0e2d \u0e15\u0e48\u0e32\u0e07\u0e2b\u0e39 \u0e41\u0e2b\u0e27\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e33\u0e44\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b  \u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e15\u0e34\u0e4a\u0e01\u0e15\u0e4a\u0e2d\u0e01(tiktok) \u0e0a\u0e47\u0e2d\u0e1b\u0e1b\u0e35\u0e49(shopee) \u0e25\u0e32\u0e0b\u0e32\u0e14\u0e49\u0e32 (lazada) \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 49\/23  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07-\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0173569000159\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e21\u0e25 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 2026\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0173569000159 \u0e2b\u0e08.\u0e01\u0e21\u0e25 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 2026 2569-07-21 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 3\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002641\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e31\u0e19\u0e19\u0e34\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002641 \u0e1a\u0e08.\u0e2a\u0e31\u0e19\u0e19\u0e34\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e40\u0e16\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 90\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003211\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e39\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003211 \u0e2b\u0e08.\u0e1e\u0e39\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 2569-07-21 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e40\u0e28\u0e29\u0e02\u0e22\u0e30 \u0e02\u0e22\u0e30\u0e21\u0e39\u0e25\u0e1d\u0e2d\u0e22 \u0e01\u0e32\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07  \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e41\u0e25\u0e30\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e49\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038092\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e34\u0e23\u0e31\u0e13\u0e22\u0e4c \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038092 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e34\u0e23\u0e31\u0e13\u0e22\u0e4c \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 (visa) \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e2d \u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 30\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038106\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038106 \u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e16\u0e23\u0e48\u0e27\u0e21 \u904b\u8f38\u30fb\u7269\u6d41 100\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038149\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e19\u0e17\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038149 \u0e1a\u0e08.\u0e19\u0e19\u0e17\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e23\u0e16\u0e41\u0e1a\u0e04\u0e42\u0e2e \u0e23\u0e16\u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 413\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038165\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e44\u0e19\u0e19\u0e4c \u0e40\u0e08\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038165 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e44\u0e19\u0e19\u0e4c \u0e40\u0e08\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e1a\u0e32\u0e23\u0e4c \u0e40\u0e25\u0e32\u0e19\u0e08\u0e4c \u0e14\u0e34\u0e2a\u0e42\u0e01\u0e49\u0e40\u0e18\u0e04 \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e14 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e41\u0e1c\u0e48\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e23\u0e33 \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u5bbf\u6cca\u30fb\u98f2\u98df 110\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038173\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e35 \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038173 \u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e35 \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 10  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19\u0e2a\u0e32\u0e22 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038190\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e44\u0e17\u0e22\u0e2d\u0e21\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038190 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e44\u0e17\u0e22\u0e2d\u0e21\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 149\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038203\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e01\u0e34\u0e15\u0e15\u0e34\u0e4c\u0e23\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038203 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e01\u0e34\u0e15\u0e15\u0e34\u0e4c\u0e23\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 49\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038211\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038211 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47222 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e21\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 186  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038271\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e1e\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038271 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e1e\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 65\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038289\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e2d\u0e35\u0e2d\u0e35 \u0e17\u0e39 \u0e0b\u0e31\u0e1e\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038289 \u0e1a\u0e08.\u0e0b\u0e35\u0e2d\u0e35\u0e2d\u0e35 \u0e17\u0e39 \u0e0b\u0e31\u0e1e\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001316\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e01\u0e2d.\u0e41\u0e01\u0e07\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001316 \u0e2b\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e01\u0e2d.\u0e41\u0e01\u0e07 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 172\/173  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009653\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e19\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96303\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96303\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009653 \u0e1a\u0e08.\u0e04\u0e19\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 96303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 157\/4  \u0e16\u0e19\u0e19\u0e23\u0e34\u0e21\u0e19\u0e49\u0e33 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009661\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e19\u0e01\u0e23\u0e35\u0e40\u0e14\u0e35\u0e22\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009661 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e19\u0e01\u0e23\u0e35\u0e40\u0e14\u0e35\u0e22\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 63113 \u0e08\u0e33\u0e2b\u0e48\u0e32\u0e22\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e42\u0e14\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 24\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009670\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009670 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47215 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/135  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009688\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e17\u0e27\u0e35 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009688 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e17\u0e27\u0e35 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u5efa\u8a2d 112\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003931\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003931 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 3 \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07 \u0e41\u0e08\u0e49\u0e07\u0e2d\u0e2d\u0e01  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 3 \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e31\u0e1a\u0e41\u0e08\u0e31\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27 \u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 3 \u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 27\/139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003949\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e42\u0e15\u0e19 \u0e41\u0e21\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43302\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43302\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003949 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e42\u0e15\u0e19 \u0e41\u0e21\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 43302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e1c\u0e19\u0e31\u0e07 \u0e14\u0e49\u0e27\u0e22\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 \u0e2b\u0e34\u0e19\u0e41\u0e01\u0e23\u0e19\u0e34\u0e15 \u0e2b\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003957\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e13\u0e34\u0e2a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003957 \u0e1a\u0e08.\u0e28\u0e13\u0e34\u0e2a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e1b \u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e0a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e1b\u0e44\u0e2a\u0e49\u0e41\u0e15\u0e01 \u88fd\u9020 116  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0275569001148\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e23\u0e18\u0e19\u0e32\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001148 \u0e1a\u0e08.\u0e27\u0e23\u0e18\u0e19\u0e32\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32  \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 342  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002796\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e1b\u0e14 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002796 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e41\u0e1b\u0e14 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 2569-07-21 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002800\",\"name_th\":\"\u0e2b\u0e08.\u0e13 \u0e2a\u0e30\u0e2b\u0e27\u0e32\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"91031\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"91031\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002800 \u0e2b\u0e08.\u0e13 \u0e2a\u0e30\u0e2b\u0e27\u0e32\u0e19 2569-07-21 1000000 91031 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e27\u0e19\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e2a\u0e27\u0e19\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e2a\u0e27\u0e19\u0e1e\u0e24\u0e01\u0e29\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2a\u0e27\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08 \u82b8\u8853\u30fb\u5a2f\u697d 131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001970\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e19\u0e34\u0e0a \u0e44\u0e25\u0e19\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001970 \u0e1a\u0e08.\u0e1f\u0e34\u0e19\u0e34\u0e0a \u0e44\u0e25\u0e19\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 178  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e34\u0e25\u0e32\u0e17\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0323569000572\",\"name_th\":\"\u0e2b\u0e08.\u0e2d.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1f\u0e35\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000572 \u0e2b\u0e08.\u0e2d.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1f\u0e35\u0e14 2569-07-21 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 400  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0343569001978\",\"name_th\":\"\u0e2b\u0e08.96 \u0e44\u0e2d\u0e17\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001978 \u0e2b\u0e08.96 \u0e44\u0e2d\u0e17\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-21 1000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0343569001986\",\"name_th\":\"\u0e2b\u0e08.45 \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e2a\u0e42\u0e15\u0e27\u0e4c\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001986 \u0e2b\u0e08.45 \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e2a\u0e42\u0e15\u0e27\u0e4c 2569-07-21 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003310\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08(2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003310 \u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08(2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e14 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 97  \u0e16\u0e19\u0e19\u0e0a\u0e22\u0e32\u0e07\u0e01\u0e39\u0e23 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003336\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e1a\u0e35 \u0e40\u0e2a\u0e01\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003336 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e1a\u0e35 \u0e40\u0e2a\u0e01\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 146  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0365569001465\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e44\u0e1e\u0e1e\u0e4c\u0e44\u0e25\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001465 \u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e44\u0e1e\u0e1e\u0e4c\u0e44\u0e25\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u5efa\u8a2d 329  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0403569003244\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e0a\u0e32\u0e27\u0e14\u0e35289 \u0e40\u0e2e\u0e1f\u0e27\u0e35\u0e48 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46631\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46631\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003244 \u0e2b\u0e08.\u0e2a\u0e38\u0e0a\u0e32\u0e27\u0e14\u0e35289 \u0e40\u0e2e\u0e1f\u0e27\u0e35\u0e48 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-21 1000000 46631 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e16\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e2d\u0e19\u0e2b\u0e31\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006989\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e20\u0e39\u0e40\u0e27\u0e35\u0e22\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006989 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e20\u0e39\u0e40\u0e27\u0e35\u0e22\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006997\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e14\u0e32\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006997 \u0e1a\u0e08.\u0e25\u0e14\u0e32\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001675\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2d \u0e0b\u0e35\u0e27\u0e34\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001675 \u0e2b\u0e08.\u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2d \u0e0b\u0e35\u0e27\u0e34\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 251  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001683\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e15\u0e23\u0e35\u0e19\u0e38\u0e0a \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001683 \u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e15\u0e23\u0e35\u0e19\u0e38\u0e0a \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-21 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001691\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35.\u0e40\u0e2d\u0e1f.\u0e1a\u0e34\u0e49\u0e27\u0e15\u0e35\u0e49\u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001691 \u0e2b\u0e08.\u0e1a\u0e35.\u0e40\u0e2d\u0e1f.\u0e1a\u0e34\u0e49\u0e27\u0e15\u0e35\u0e49\u0e0a\u0e47\u0e2d\u0e1b 2569-07-21 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003840\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003840 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 78109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e17\u0e33\u0e07\u0e32\u0e19,\u0e44\u0e1b\u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 154\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0445569001758\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e35\u0e22\u0e27\u0e1e\u0e32\u0e23\u0e27\u0e22\u0e2e\u0e34\u0e27\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001758 \u0e1a\u0e08.\u0e40\u0e02\u0e35\u0e22\u0e27\u0e1e\u0e32\u0e23\u0e27\u0e22\u0e2e\u0e34\u0e27\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e27\u0e34\u0e18\u0e35 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0505569016380\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e2a\u0e25\u0e35\u0e48 \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016380 \u0e1a\u0e08.\u0e40\u0e19\u0e2a\u0e25\u0e35\u0e48 \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e0b\u0e31\u0e01 \u0e2d\u0e1a \u0e23\u0e35\u0e14 \u0e0b\u0e31\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e02\u0e08\u0e31\u0e14\u0e04\u0e23\u0e32\u0e1a \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 678\/603  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016398\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e25\u0e1e \u0e22\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2e\u0e19\u0e14\u0e4c\u0e2a \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016398 \u0e1a\u0e08.\u0e41\u0e04\u0e25\u0e1e \u0e22\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e2e\u0e19\u0e14\u0e4c\u0e2a \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e32\u0e22\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 270  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016428\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21  \u0e27\u0e34\u0e04\u0e42\u0e17\u0e23\u0e35\u0e48 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e25\u0e2d\u0e27\u0e4c \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016428 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21  \u0e27\u0e34\u0e04\u0e42\u0e17\u0e23\u0e35\u0e48 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e25\u0e2d\u0e27\u0e4c \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e23\u0e23\u0e16\u0e04\u0e14\u0e35\u0e04\u0e27\u0e32\u0e21 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 177  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016479\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e14\u0e23\u0e34\u0e0a\u0e14\u0e32\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016479 \u0e1a\u0e08.\u0e2a\u0e38\u0e14\u0e23\u0e34\u0e0a\u0e14\u0e32\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222\/419  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e01\u0e19\u0e01 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e212 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0535569000807\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e25\u0e0a\u0e31\u0e22 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000807 \u0e1a\u0e08.\u0e0a\u0e25\u0e0a\u0e31\u0e22 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 89\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0545569000831\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30 \u0e40\u0e04\u0e32\u0e17\u0e19\u0e4c \u0e44\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000831 \u0e1a\u0e08.\u0e2d\u0e30 \u0e40\u0e04\u0e32\u0e17\u0e19\u0e4c \u0e44\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 229\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0555569000611\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000611 \u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 108  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32\u0e01\u0e2d\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 13 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002255\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07\u0e22\u0e19\u0e15\u0e4c\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002255 \u0e2b\u0e08.\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07\u0e22\u0e19\u0e15\u0e4c 2569-07-21 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22  \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e22\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e22\u0e32\u0e07\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004713\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e27\u0e32\u0e25\u0e32 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004713 \u0e1a\u0e08.\u0e0a\u0e32\u0e27\u0e32\u0e25\u0e32 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e40\u0e08\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569002175\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e42\u0e1f\u0e19\u0e25\u0e32\u0e14\u0e22\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002175 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e42\u0e1f\u0e19\u0e25\u0e32\u0e14\u0e22\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e08\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 357\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0655569002337\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e1f \u0e42\u0e1a\u0e19\u0e31\u0e19\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10779\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10779\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002337 \u0e1a\u0e08.\u0e40\u0e0a\u0e1f \u0e42\u0e1a\u0e19\u0e31\u0e19\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 10779 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u88fd\u9020 145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0663569000570\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e28\u0e34\u0e23\u0e34 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0663569000570 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e28\u0e34\u0e23\u0e34 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0705569003308\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e1e\u0e35 \u0e42\u0e1f\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003308 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e1e\u0e35 \u0e42\u0e1f\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e25\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 (\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07) \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 (\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07) \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e38\u0e14 \u0e08\u0e33\u0e19\u0e33 \u0e42\u0e14\u0e22\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0b\u0e4c\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14 \u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1a\u0e48\u0e07\u0e08\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e48\u0e2d\u0e19\u0e0a\u0e33\u0e23\u0e30\u0e04\u0e48\u0e32\u0e07\u0e27\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d \u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 143  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002735\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e01\u0e32\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002735 \u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e01\u0e32\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 190\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000692\",\"name_th\":\"\u0e2b\u0e08.\u0e2a.\u0e2a\u0e38\u0e0a\u0e34\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000692 \u0e2b\u0e08.\u0e2a.\u0e2a\u0e38\u0e0a\u0e34\u0e19 2569-07-21 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2  \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e19\u0e28\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001109\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e19.\u0e17\u0e35. \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001109 \u0e2b\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e19.\u0e17\u0e35. \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c 2569-07-21 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e02\u0e22\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e0b\u0e32\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007664\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e40\u0e27\u0e22\u0e4c \u0e1e\u0e35 \u0e42\u0e1f\u0e25\u0e27\u0e4c\u0e41\u0e1f\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007664 \u0e1a\u0e08.\u0e40\u0e04 \u0e40\u0e27\u0e22\u0e4c \u0e1e\u0e35 \u0e42\u0e1f\u0e25\u0e27\u0e4c\u0e41\u0e1f\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007681\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20131\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20131\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007681 \u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 20131 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007699\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007699 \u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e38\u0e07 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0773569000439\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e35\u0e23\u0e35 \u0e42\u0e22\u0e18\u0e32\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0773569000439 \u0e2b\u0e08.\u0e04\u0e35\u0e23\u0e35 \u0e42\u0e22\u0e18\u0e32 2569-07-21 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 10\/140  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0775569003073\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19\u0e04\u0e2d\u0e21\u0e42\u0e21\u0e14\u0e34\u0e15\u0e35\u0e49\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003073 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19\u0e04\u0e2d\u0e21\u0e42\u0e21\u0e14\u0e34\u0e15\u0e35\u0e49\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e01\u0e4a\u0e32\u0e0b \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e02\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35\/324  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0803569001051\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e2a\u0e15\u0e35\u0e25\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001051 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e2a\u0e15\u0e35\u0e25 2569-07-21 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0803569001060\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e14\u0e35\u0e1a\u0e35 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001060 \u0e2b\u0e08.\u0e40\u0e08\u0e14\u0e35\u0e1a\u0e35 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 2569-07-21 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002777\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e39 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002777 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e39 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5efa\u8a2d 54\/116  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e04\u0e23\u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e49\u0e19\u0e0b\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e34\u0e14\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002793\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e23\u0e35\u0e44\u0e0b\u0e04\u0e25\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002793 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e23\u0e35\u0e44\u0e0b\u0e04\u0e25\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 27\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569013400\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e31\u0e1f\u0e41\u0e0b\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01289\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01289\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013400 \u0e1a\u0e08.\u0e17\u0e31\u0e1f\u0e41\u0e0b\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 01289 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e1e\u0e32\u0e30 \u0e1b\u0e25\u0e39\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1e\u0e37\u0e0a \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e0a\u0e48\u0e2d\u0e14\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 46\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013426\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e17\u0e35\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013426 \u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e17\u0e35\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 42\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013442\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35 \u0e27\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013442 \u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35 \u0e27\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 9\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013477\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e13\u0e35\u0e18\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013477 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e13\u0e35\u0e18\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 47190 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07 \u0e2b\u0e34\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e19\u0e31\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/67  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010648\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010648 \u0e1a\u0e08.\u0e01\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e2d\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e35\u0e14\u0e1c\u0e49\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 7\/11  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e17\u0e48\u0e32\u0e42\u0e23\u0e07\u0e0a\u0e49\u0e32\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0903569001735\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e08\u0e35\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10795\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10795\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001735 \u0e2b\u0e08.\u0e28\u0e08\u0e35\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e44\u0e17\u0e22 2569-07-21 1000000 10795 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e2b\u0e25\u0e2d\u0e14 \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e0b\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e1a\u0e14 \u88fd\u9020 33\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001743\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e23\u0e34\u0e07\u0e43\u0e08\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1e\u0e25\u0e31\u0e2a\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001743 \u0e2b\u0e08.\u0e08\u0e23\u0e34\u0e07\u0e43\u0e08\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1e\u0e25\u0e31\u0e2a 2569-07-21 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e1e\u0e48\u0e27\u0e07  \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 11\/16  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e30\u0e40\u0e01\u0e29 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005961\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005961 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e25\u0e1f\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 337\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001095\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e27\u0e34\u0e19 \u0e21\u0e32\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001095 \u0e1a\u0e08.\u0e40\u0e04\u0e27\u0e34\u0e19 \u0e21\u0e32\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0935569000854\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e17\u0e31\u0e25 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000854 \u0e1a\u0e08.\u0e40\u0e21\u0e17\u0e31\u0e25 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e2a\u0e15\u0e47\u0e2d\u0e04\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 \u0e40\u0e28\u0e29\u0e17\u0e2d\u0e07\u0e40\u0e40\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21  \u0e40\u0e28\u0e29\u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0955569000609\",\"name_th\":\"\u0e1a\u0e08.\u0e27.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000609 \u0e1a\u0e08.\u0e27.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c  \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e23\u0e16\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121\/9  \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e42\u0e23\u0e23\u0e2a \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0965569000544\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0965569000544 \u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5efa\u8a2d 170  \u0e16\u0e19\u0e19\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0965569000552\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e2d\u0e30 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0965569000552 \u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e2d\u0e30 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e31\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 170  \u0e16\u0e19\u0e19\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569007790\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e40\u0e1e\u0e0a\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007790 \u0e2b\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e40\u0e1e\u0e0a\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02 2569-07-20 1000000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 333\/79  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 the city \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 3 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007811\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1f\u0e34\u0e0a \u0e41\u0e17\u0e07\u0e04\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007811 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1f\u0e34\u0e0a \u0e41\u0e17\u0e07\u0e04\u0e4c 2569-07-20 1000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e39\u0e49\u0e1b\u0e25\u0e32\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 313\/11  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 54 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007820\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e21\u0e40\u0e19\u0e48 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007820 \u0e2b\u0e08.\u0e42\u0e21\u0e40\u0e19\u0e48 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 2569-07-20 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e22\u0e32\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e49\u0e27\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 534  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 44 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136044\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e41\u0e23\u0e1a\u0e1a\u0e34\u0e17 1829 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28160\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28160\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136044 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e41\u0e23\u0e1a\u0e1a\u0e34\u0e17 1829 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 28160 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e01\u0e23\u0e21\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e19\u0e33\u0e40\u0e02\u0e31\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0a\u0e34\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14 \u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 1131\/44  \u0e2d\u0e32\u0e04\u0e32\u0e2332  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 44 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e17\u0e23\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e322 \u0e16\u0e19\u0e19\u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136061\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e4c\u0e17\u0e15\u0e31\u0e19\u0e2d\u0e21\u0e22\u0e34\u0e49\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136061 \u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e4c\u0e17\u0e15\u0e31\u0e19\u0e2d\u0e21\u0e22\u0e34\u0e49\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74\/4  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e19\u0e2d\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136079\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e2a\u0e17\u0e34\u0e04 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136079 \u0e1a\u0e08.\u0e40\u0e19\u0e2a\u0e17\u0e34\u0e04 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 68201 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 20  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e32\u0e29\u0e0f\u0e23\u0e4c 1 \u0e41\u0e22\u0e01 3 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e43\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136087\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35.\u0e1a\u0e35.\u0e40\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136087 \u0e1a\u0e08.\u0e1a\u0e35.\u0e1a\u0e35.\u0e40\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e14\u0e34\u0e1a \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27 \u0e0a\u0e32 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e42\u0e01\u0e42\u0e01\u0e49 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/262  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 3 \u0e0b.28\/1 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136095\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136095 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 63113 \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07 (e-marketplace): \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e02\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 573\/105  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0739 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136141\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e22 \u0e0a\u0e35\u0e2a\u0e40\u0e04\u0e49\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136141 \u0e1a\u0e08.\u0e0b\u0e2d\u0e22 \u0e0a\u0e35\u0e2a\u0e40\u0e04\u0e49\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 61  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136168\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e1a\u0e39\u0e2a\u0e17\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136168 \u0e1a\u0e08.\u0e23\u0e35\u0e1a\u0e39\u0e2a\u0e17\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07 \u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u533b\u7642\u30fb\u798f\u7949 323  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e40\u0e1e\u0e25\u0e2a \u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 403\/1-403\/2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 55(\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136176\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e0a\u0e31\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e35\u0e0b\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136176 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e0a\u0e31\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e35\u0e0b\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136184\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136184 \u0e1a\u0e08.\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a\u0e2a\u0e34\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1168\/90  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e2a\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136192\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e19\u0e32 \u0e2d\u0e34\u0e19\u0e44\u0e0b\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136192 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e19\u0e32 \u0e2d\u0e34\u0e19\u0e44\u0e0b\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48 \u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 565  \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136206\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136206 \u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 999\/28  \u0e16\u0e19\u0e1901 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136214\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e23\u0e34\u0e0b\u0e40\u0e0b \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136214 \u0e1a\u0e08.\u0e04\u0e23\u0e32\u0e23\u0e34\u0e0b\u0e40\u0e0b \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 119\/9  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136222\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e25\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136222 \u0e1a\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e25\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e. \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u533b\u7642\u30fb\u798f\u7949 30  \u0e0b\u0e2d\u0e22 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c 18\/7 \u0e41\u0e22\u0e01 22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136231\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e15\u0e4c \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136231 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e15\u0e4c \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 79\/86  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 29 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136265\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e35 \u0e27\u0e32\u0e22 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52293\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52293\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136265 \u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e35 \u0e27\u0e32\u0e22 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 52293 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e1e\u0e47\u0e04\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 827\/15  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e0b\u0e2d\u0e2245 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136281\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2a\u0e15\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87100\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87100\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136281 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2a\u0e15\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 87100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e07 \u533b\u7642\u30fb\u798f\u7949 2566\/56  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136303\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e23\u0e23\u0e16\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136303 \u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e2d\u0e23\u0e23\u0e16\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 15\/126  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136311\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136311 \u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 79110 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e2e\u0e31\u0e19\u0e19\u0e35\u0e21\u0e39\u0e19 \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e23\u0e31\u0e01 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 44\/325  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e31\u0e2a\u0e2a\u0e23 27 \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.\u0e59 \u0e0b.87 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136320\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e44\u0e2d\u0e08\u0e35 \u0e44\u0e2d\u0e2d\u0e35\u0e40\u0e2d\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136320 \u0e1a\u0e08.\u0e1a\u0e35\u0e44\u0e2d\u0e08\u0e35 \u0e44\u0e2d\u0e2d\u0e35\u0e40\u0e2d\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 20111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e4a\u0e32\u0e0b\u0e2d\u0e2d\u0e01\u0e0b\u0e34\u0e40\u0e08\u0e19 \u0e01\u0e4a\u0e32\u0e0b\u0e44\u0e19\u0e42\u0e15\u0e23\u0e40\u0e08\u0e19 \u0e01\u0e4a\u0e32\u0e0b\u0e2d\u0e32\u0e23\u0e4c\u0e01\u0e2d\u0e19 \u0e2d\u0e2d\u0e01\u0e0b\u0e34\u0e40\u0e08\u0e19\u0e40\u0e2b\u0e25\u0e27 \u0e44\u0e19\u0e42\u0e15\u0e23\u0e40\u0e08\u0e19\u0e40\u0e2b\u0e25\u0e27  \u0e2d\u0e32\u0e23\u0e4c\u0e01\u0e2d\u0e19\u0e40\u0e2b\u0e25\u0e27 \u0e44\u0e2e\u0e42\u0e14\u0e23\u0e40\u0e08\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e41\u0e01\u0e4a\u0e2a\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e41\u0e01\u0e4a\u0e2a\u0e2b\u0e38\u0e07\u0e15\u0e49\u0e21 \u0e41\u0e01\u0e4a\u0e2a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e01\u0e4a\u0e2a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e2b\u0e25\u0e27  \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e1a\u0e23\u0e01 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e23\u0e34\u0e04 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e15\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e14\u0e35\u0e40\u0e0b\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e08\u0e32\u0e23\u0e1a\u0e35  \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e14\u0e34\u0e1a \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a  \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e40\u0e04\u0e21\u0e35 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e19\u0e35\u0e49      \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e19\u0e35\u0e49\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e14\u0e49\u0e27\u0e22 \u88fd\u9020 1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2a\u0e35\u0e25\u0e21 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 24 \u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e41\u0e27\u0e19\u0e15\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136338\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136338 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e2d\u0e41\u0e2d\u0e25\u0e2d\u0e35\u0e14\u0e35 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 148  \u0e0b\u0e2d\u0e22 \u0e41\u0e1a\u0e23\u0e34\u0e48\u0e07 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136389\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e19\u0e40\u0e14\u0e21\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136389 \u0e1a\u0e08.\u0e1f\u0e34\u0e19\u0e40\u0e14\u0e21\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 558\/581  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136401\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e23\u0e32\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136401 \u0e1a\u0e08.\u0e08\u0e35\u0e23\u0e32\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e0a\u0e32\u0e22 \u0e2b\u0e0d\u0e34\u0e07 \u0e40\u0e14\u0e47\u0e01 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/117  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 28 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136427\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136427 \u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 128  \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 28\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136486\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136486 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 22220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e49\u0e32\u0e2a\u0e1b\u0e31\u0e19\u0e1a\u0e2d\u0e19\u0e14\u0e4c (spunbond) \u0e1c\u0e49\u0e32\u0e44\u0e21\u0e48\u0e17\u0e2d (non-woven fabric) \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22 \u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e42\u0e1e\u0e25\u0e35\u0e42\u0e1e\u0e23\u0e1e\u0e35\u0e25\u0e35\u0e19 (pp) \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 589  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136494\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136494 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e34\u0e40\u0e23\u0e34\u0e48\u0e21 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e08\u0e31\u0e14\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 32\/40  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136559\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136559 \u0e1a\u0e08.\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 45302 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 274  \u0e16\u0e19\u0e19\u0e27\u0e23\u0e08\u0e31\u0e01\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136567\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e44\u0e2d\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136567 \u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e44\u0e2d\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 400\/127  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136583\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e44\u0e17\u0e22 \u0e14\u0e34\u0e08\u0e34\u0e15\u0e31\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136583 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e44\u0e17\u0e22 \u0e14\u0e34\u0e08\u0e34\u0e15\u0e31\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e21\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u60c5\u5831\u901a\u4fe1\u30fbit 8\/108  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 47 \u0e41\u0e22\u0e01 6-11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136591\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e25\u0e35\u0e21\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136591 \u0e1a\u0e08.\u0e01\u0e25\u0e35\u0e21\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 752\/44  \u0e16\u0e19\u0e19\u0e02\u0e38\u0e21\u0e17\u0e2d\u0e07-\u0e25\u0e33\u0e15\u0e49\u0e2d\u0e22\u0e15\u0e34\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136605\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e2d. \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136605 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e2d. \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49  \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 119  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e35\u0e44\u0e2d\u0e40\u0e2d\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2d24 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e21\u0e40\u0e2b\u0e2a\u0e31\u0e01\u0e02\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136648\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e40\u0e21\u0e14\u0e34\u0e1e\u0e25\u0e31\u0e2a \u0e25\u0e32\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136648 \u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e40\u0e21\u0e14\u0e34\u0e1e\u0e25\u0e31\u0e2a \u0e25\u0e32\u0e1a\u0e2d\u0e23\u0e32\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e41\u0e25\u0e47\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u533b\u7642\u30fb\u798f\u7949 428\/59  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136681\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39.\u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136681 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39.\u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e25\u0e32\u0e14  \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e  \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 1111\/104  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e38\u0e23\u0e32\u0e2a\u0e34\u0e23\u0e34 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136699\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e21\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136699 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e21\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 444\/134  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 162\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136702\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e21 \u0e40\u0e0b\u0e25\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136702 \u0e1a\u0e08.\u0e41\u0e2d\u0e21 \u0e40\u0e0b\u0e25\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/341  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e2d\u0e15\u0e42\u0e15\u0e49 \u0e1a\u0e32\u0e22 \u0e0a\u0e19\u0e31\u0e19\u0e18\u0e23 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136729\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136729 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15(e-commerce) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1083\/4-5  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 71 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136745\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136745 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 775\/39  \u0e16\u0e19\u0e19\u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136761\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e04.\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136761 \u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e04.\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 3109  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023894\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023894 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023908\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e42\u0e23\u0e30\u0e27\u0e30\u0e1b\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77400\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77400\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023908 \u0e1a\u0e08.\u0e04\u0e38\u0e42\u0e23\u0e30\u0e27\u0e30\u0e1b\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 77400 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e1b\u0e34\u0e14\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0b\u0e2a\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e22\u0e32\u0e22\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e02\u0e22\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0b\u0e2a\u0e4c \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 98\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023916\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e2d\u0e38\u0e14\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023916 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e2d\u0e38\u0e14\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 78101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 (artist management) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e04\u0e48\u0e32\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e37\u0e48\u0e2d \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e02\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e43\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 305\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023924\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023924 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/36  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e17\u0e27\u0e35\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023932\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e31\u0e15\u0e19\u0e32\u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023932 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e31\u0e15\u0e19\u0e32\u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e48\u0e07-\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e38\u0e23\u0e32 \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2080\/443  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023959\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e35\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31003\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31003\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023959 \u0e1a\u0e08.\u0e2e\u0e35\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 31003 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19 \u0e1f\u0e39\u0e01 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u88fd\u9020 234\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024017\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e2d\u0e2a \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024017 \u0e1a\u0e08.\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e2d\u0e2a \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e2a\u0e21 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e1a\u0e39\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 31\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027270\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e14\u0e27\u0e34\u0e40\u0e28\u0e29 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01461\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01461\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027270 \u0e1a\u0e08.\u0e2a\u0e38\u0e14\u0e27\u0e34\u0e40\u0e28\u0e29 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 01461 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e44\u0e02\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e02\u0e48 \u8fb2\u6797\u6c34\u7523 101\/320  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e31\u0e13\u0e11\u0e19\u0e32-\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027296\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e1b\u0e14\u0e28\u0e39\u0e19\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027296 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e1b\u0e14\u0e28\u0e39\u0e19\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e1e\u0e31\u0e14\u0e25\u0e21\u0e44\u0e2d\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e31\u0e14\u0e25\u0e21\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21\u0e17\u0e48\u0e2d \u0e17\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e25\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 123\/80  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027300\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e27\u0e35\u0e44\u0e2d\u0e1e\u0e35\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027300 \u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e27\u0e35\u0e44\u0e2d\u0e1e\u0e35\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 59\/934  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e25\u0e25\u0e32\u0e08\u0e08\u0e34\u0e42\u0e2d \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32 - \u0e28\u0e32\u0e25\u0e32\u0e22\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 62 \u0e16\u0e19\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027318\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027318 \u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027326\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027326 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 46  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e13\u0e23\u0e07\u0e04\u0e4c\u0e2a\u0e38\u0e02\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c \u0e0b\u0e2d\u0e22 \u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 6 \u0e41\u0e22\u0e01 6 \/3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027377\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e08\u0e2a\u0e15\u0e34\u0e01 \u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e2d\u0e40\u0e2d\u0e0b\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027377 \u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e08\u0e2a\u0e15\u0e34\u0e01 \u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e2d\u0e40\u0e2d\u0e0b\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 64201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e17\u0e38\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 89\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 22 \u0e41\u0e22\u0e01 11 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027385\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027385 \u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e39\u0e01\u0e02\u0e32\u0e14\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e41\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u9271\u696d\u30fb\u63a1\u77f3 162\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027393\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e19\u0e33\u0e42\u0e0a\u0e04 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027393 \u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e19\u0e33\u0e42\u0e0a\u0e04 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e39\u0e01\u0e02\u0e32\u0e14\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e41\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u9271\u696d\u30fb\u63a1\u77f3 162\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027423\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027423 \u0e1a\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19, \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027431\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49\u0e40\u0e1f\u0e23\u0e21\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027431 \u0e1a\u0e08.\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e42\u0e1f\u0e42\u0e15\u0e49\u0e40\u0e1f\u0e23\u0e21\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 74200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e25\u0e34\u0e15\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e39\u0e1b \u0e15\u0e23\u0e32\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 61  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002534\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e22\u0e39\u0e2a\u0e01\u0e23\u0e35\u0e19\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46495\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46495\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002534 \u0e2b\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e22\u0e39\u0e2a\u0e01\u0e23\u0e35\u0e19 2569-07-20 1000000 46495 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e41\u0e01\u0e49\u0e27\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e25\u0e32\u0e22\u0e41\u0e01\u0e49\u0e27\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 211\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002542\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e31\u0e04 \u0e1b\u0e34\u0e42\u0e15\u0e23\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002542 \u0e2b\u0e08.\u0e0a\u0e31\u0e04 \u0e1b\u0e34\u0e42\u0e15\u0e23 2569-07-20 1000000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e04\u0e25\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022201\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e21\u0e17\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022201 \u0e1a\u0e08.\u0e41\u0e1e\u0e21\u0e17\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1e\u0e25\u0e2d\u0e22\u0e44\u0e14\u0e49 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07 \u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e23\u0e23\u0e21  \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 789  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022227\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e25\u0e2d\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022227 \u0e1a\u0e08.\u0e1f\u0e34\u0e25\u0e2d\u0e34\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 109\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022235\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e48\u0e32\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022235 \u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e48\u0e32\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 shopee, lazada, tiktok,youtube, facebook, instagram \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/551  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022243\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e17 \u0e40\u0e04\u0e21 \u0e2d\u0e34\u0e19\u0e19\u0e2d\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022243 \u0e1a\u0e08.\u0e41\u0e2d\u0e17 \u0e40\u0e04\u0e21 \u0e2d\u0e34\u0e19\u0e19\u0e2d\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71\/356  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022251\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e1e\u0e35 \u0e01\u0e23\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022251 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e1e\u0e35 \u0e01\u0e23\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 49\/108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022286\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e19\u0e32\u0e1e\u0e31\u0e12 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 95 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022286 \u0e1a\u0e08.\u0e0a\u0e19\u0e32\u0e1e\u0e31\u0e12 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 95 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 150\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022324\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e1b\u0e23 \u0e42\u0e21\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022324 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e1b\u0e23 \u0e42\u0e21\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e40\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e42\u0e0a\u0e47\u0e04 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e2a\u0e40\u0e1b\u0e22\u0e4c\u0e02\u0e08\u0e31\u0e14\u0e04\u0e23\u0e32\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e22\u0e32\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022341\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2006  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022341 \u0e1a\u0e08.\u0e40\u0e04\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2006  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 99\/410  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e23\u0e39\u0e0d\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e1b\u0e32\u0e23\u0e4c\u0e04\u0e27\u0e34\u0e25\u0e25\u0e4c\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022367\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e14\u0e35\u0e1e\u0e2d 1979 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022367 \u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e14\u0e35\u0e1e\u0e2d 1979 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47190 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/14  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e1e\u0e23 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022375\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e1e\u0e25\u0e31\u0e2a\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022375 \u0e1a\u0e08.\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e1e\u0e25\u0e31\u0e2a\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e41\u0e25\u0e47\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u533b\u7642\u30fb\u798f\u7949 45\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004733\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e2b\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004733 \u0e1a\u0e08.\u0e2a\u0e2b\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e02\u0e49\u0e32\u0e07\u0e32\u0e19  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e16\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u533b\u7642\u30fb\u798f\u7949 1\/184  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0155569000584\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e21\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000584 \u0e1a\u0e08.\u0e1e\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e21\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48, \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19, \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0185569000509\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0185569000509 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46  \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 (\u0e01\u0e4a\u0e32\u0e0b \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19)  \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e40\u0e15\u0e32\u0e2b\u0e25\u0e2d\u0e21 \u0e17\u0e48\u0e2d\u0e1c\u0e36\u0e48\u0e07\u0e25\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e19\u0e49\u0e33\u0e23\u0e49\u0e2d\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07  \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e48\u0e2d\u0e01\u0e4a\u0e32\u0e0b\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e4a\u0e32\u0e0b\u0e2d\u0e2d\u0e01\u0e0b\u0e34\u0e40\u0e08\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e17\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 160\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0203569003190\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003190 \u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-20 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e38\u0e14 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e28\u0e29\u0e27\u0e31\u0e15\u0e16\u0e38\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e28\u0e29\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e2d\u0e42\u0e25\u0e2b\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 336\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037851\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e23\u0e34\u0e19\u0e22\u0e32 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037851 \u0e1a\u0e08.\u0e2a\u0e23\u0e34\u0e19\u0e22\u0e32 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e1a\u0e1a\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200\/97  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037886\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037886 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e41\u0e23\u0e07\u0e15\u0e48\u0e33  \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32  \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19  \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 15\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037894\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e01\u0e0b\u0e4c\u0e0b\u0e2d\u0e23\u0e48\u0e32 \u0e1e\u0e31\u0e17\u0e22\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037894 \u0e1a\u0e08.\u0e40\u0e25\u0e01\u0e0b\u0e4c\u0e0b\u0e2d\u0e23\u0e48\u0e32 \u0e1e\u0e31\u0e17\u0e22\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 69100 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35 \u0e1f\u0e49\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07 \u0e15\u0e48\u0e2d\u0e2a\u0e39\u0e49\u0e04\u0e14\u0e35\u0e43\u0e19\u0e28\u0e32\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e31\u0e49\u0e19\u0e28\u0e32\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\/\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 (\u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e21\u0e2a\u0e23\u0e23\u0e1e\u0e32\u0e01\u0e23, \u0e01\u0e23\u0e21\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e19\u0e35\u0e1b\u0e23\u0e30\u0e19\u0e2d\u0e21\u0e22\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 214\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037908\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e04\u0e32\u0e2a\u0e40\u0e0b\u0e34\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037908 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e04\u0e32\u0e2a\u0e40\u0e0b\u0e34\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e49\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 686\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037916\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e2a \u0e40\u0e04 1979 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037916 \u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e2a \u0e40\u0e04 1979 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 560\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037941\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e0a\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037941 \u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e0a\u0e19\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e19\u0e49\u0e33\u0e0a\u0e07 \u0e19\u0e49\u0e33\u0e2b\u0e27\u0e32\u0e19 \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e31\u0e48\u0e07\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 120\/323  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037959\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e22\u0e21\u0e34\u0e1e\u0e25\u0e31\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037959 \u0e1a\u0e08.\u0e42\u0e22\u0e21\u0e34\u0e1e\u0e25\u0e31\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15\u0e1b\u0e31\u0e48\u0e19 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e31\u0e48\u0e19 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 120\/323  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037967\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e35\u0e0a\u0e31\u0e07 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037967 \u0e1a\u0e08.\u0e2a\u0e35\u0e0a\u0e31\u0e07 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u5bbf\u6cca\u30fb\u98f2\u98df 800\/108  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037975\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e27\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037975 \u0e1a\u0e08.\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e27\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 74200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e20\u0e32\u0e1e\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 142-144  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e23\u0e32\u0e0a\u0e32\u0e19\u0e04\u0e233 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037991\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e2b\u0e01\u0e2b\u0e49\u0e32 \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32303\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32303\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037991 \u0e1a\u0e08.\u0e40\u0e04\u0e2b\u0e01\u0e2b\u0e49\u0e32 \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 32303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e01\u0e38\u0e49\u0e07 \u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e47\u0e14\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e2d\u0e01 \u0e04\u0e31\u0e19\u0e40\u0e1a\u0e47\u0e14 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e0a\u0e48\u0e19 tiktok shopee lasada \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u88fd\u9020 95\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038017\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e44\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45303\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45303\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038017 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e44\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 45303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e22\u0e32\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e22\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e42\u0e04\u0e23\u0e07\u0e22\u0e32\u0e07\u0e40\u0e01\u0e48\u0e32-\u0e22\u0e32\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038033\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e48\u0e32\u0e27\u0e08\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038033 \u0e1a\u0e08.\u0e2d\u0e48\u0e32\u0e27\u0e08\u0e34\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038050\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e19\u0e09\u0e48\u0e33 \u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038050 \u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e19\u0e09\u0e48\u0e33 \u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 114\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038068\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038068 \u0e1a\u0e08.\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e34\u0e10 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 135\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009572\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e25 \u0e40\u0e04 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1e\u0e2d\u0e40\u0e23\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93299\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93299\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009572 \u0e1a\u0e08.\u0e04\u0e39\u0e25 \u0e40\u0e04 \u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e1e\u0e2d\u0e40\u0e23\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 93299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e41\u0e25\u0e30\u0e27\u0e35\u0e14\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u82b8\u8853\u30fb\u5a2f\u697d 919\/431  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e42\u0e2d \u0e19\u0e2d\u0e1f \u0e23\u0e30\u0e22\u0e2d\u0e07-\u0e1b\u0e25\u0e27\u0e01\u0e41\u0e14\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009581\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1a\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009581 \u0e1a\u0e08.\u0e17\u0e35\u0e1a\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 90\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009599\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e19\u0e38\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e28\u0e34\u0e25\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009599 \u0e1a\u0e08.\u0e2b\u0e19\u0e38\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e28\u0e34\u0e25\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (2)\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e16\u0e2a\u0e34\u0e1a\u0e25\u0e49\u0e2d \u0e23\u0e16\u0e1e\u0e48\u0e27\u0e07 \u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 (3)\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e16\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23 \u0e23\u0e16\u0e02\u0e38\u0e14 \u0e23\u0e16\u0e15\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 (4)\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (5)\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009629\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009629 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e0a\u0e38\u0e14\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e21\u0e25\u0e07 \u0e0a\u0e38\u0e14\u0e01\u0e31\u0e19\u0e15\u0e31\u0e27\u0e15\u0e48\u0e2d \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120\/76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002306\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e48\u0e32299 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002306 \u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e48\u0e32299 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 94\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003914\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e21\u0e47\u0e2d\u0e1e \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003914 \u0e1a\u0e08.\u0e14\u0e35\u0e21\u0e47\u0e2d\u0e1e \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e31\u0e14\u0e25\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1e\u0e37\u0e49\u0e19 \u0e0b\u0e31\u0e01\u0e1e\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e01\u0e23\u0e30\u0e08\u0e01 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 11\/374  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e32\u0e23\u0e27\u0e22\u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e14\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 23 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003922\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e19\u0e20\u0e31\u0e2a399 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003922 \u0e1a\u0e08.\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e19\u0e20\u0e31\u0e2a399 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01  \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0253569000506\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e0a\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66210\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66210\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0253569000506 \u0e2b\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e0a\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c 2569-07-20 1000000 66210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e25\u0e30\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 60\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007480\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e12\u0e19\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007480 \u0e1a\u0e08.\u0e1e\u0e31\u0e12\u0e19\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e19 \u533b\u7642\u30fb\u798f\u7949 37\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007510\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e25\u0e14\u0e32 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007510 \u0e1a\u0e08.\u0e40\u0e21\u0e25\u0e14\u0e32 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e19\u0e4d\u0e49\u0e32\u0e2b\u0e2d\u0e21 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/158  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e17\u0e48\u0e32\u0e15\u0e30\u0e42\u0e01 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001953\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e10\u0e1e\u0e35\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001953 \u0e1a\u0e08.\u0e1b\u0e10\u0e1e\u0e35\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01\u0e04\u0e39\u0e04\u0e25\u0e2d\u0e07 \u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30\u0e19\u0e4d\u0e49\u0e32 \u0e16\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e33\u0e04\u0e31\u0e19\u0e01\u0e31\u0e49\u0e19\u0e19\u0e4d\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e20\u0e32\u0e1e\u0e1e\u0e37\u0e49\u0e19\u0e14\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0335569001163\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e22 \u0e0a\u0e47\u0e2d\u0e1b \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79909\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79909\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001163 \u0e1a\u0e08.\u0e21\u0e32\u0e22 \u0e0a\u0e47\u0e2d\u0e1b \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 79909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 175\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569001951\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e2a\u0e20\u0e32 159\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001951 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e2a\u0e20\u0e32 159 2569-07-20 1000000 71202 \u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0343569001960\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e07\u0e2a\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001960 \u0e2b\u0e08.\u0e23\u0e31\u0e07\u0e2a\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-20 1000000 49339 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003298\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e2d\u0e14\u0e40\u0e07\u0e34\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003298 \u0e1a\u0e08.\u0e01\u0e2d\u0e14\u0e40\u0e07\u0e34\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 694  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003301\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003301 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5efa\u8a2d 242  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0373569000246\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0373569000246 \u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e17\u0e22 2569-07-20 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1e\u0e32\u0e22 \u0e40\u0e04\u0e49\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 89\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001667\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e31\u0e19\u0e15\u0e4c\u0e2a\u0e34\u0e23\u0e34 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001667 \u0e2b\u0e08.\u0e2a\u0e31\u0e19\u0e15\u0e4c\u0e2a\u0e34\u0e23\u0e34 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c 2569-07-20 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 46  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e14\u0e07\u0e41\u0e04\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003777\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e40\u0e2e\u0e07\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003777 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e40\u0e2e\u0e07\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 51  \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e28\u0e23\u0e35 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003807\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003807 \u0e1a\u0e08.\u0e40\u0e08\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003815\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e17\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003815 \u0e1a\u0e08.\u0e19\u0e31\u0e17\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e17\u0e4c (event) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 527\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e40\u0e15\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003831\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 1972 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01461\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01461\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003831 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 1972 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 01461 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e44\u0e02\u0e48\u0e40\u0e1b\u0e47\u0e14 \u0e25\u0e39\u0e01\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e01\u0e48\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e44\u0e01\u0e48\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e40\u0e1b\u0e47\u0e14 \u8fb2\u6797\u6c34\u7523 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0425569000549\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c 90 \u0e40\u0e25\u0e22 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000549 \u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c 90 \u0e40\u0e25\u0e22 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 271  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0435569001138\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e21\u0e25\u0e0a\u0e31\u0e22 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001138 \u0e1a\u0e08.\u0e01\u0e21\u0e25\u0e0a\u0e31\u0e22 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46692 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1b\u0e38\u0e4b\u0e22 \u0e1b\u0e38\u0e4b\u0e22\u0e19\u0e49\u0e33 \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e23\u0e2d\u0e07 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0445569001731\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e08\u0e1a\u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24201\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24201\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001731 \u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e08\u0e1a\u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 24201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e07\u0e34\u0e19 \u88fd\u9020 590\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0453569001071\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e31\u0e4b\u0e19\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 123\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001071 \u0e2b\u0e08.\u0e2d\u0e31\u0e4b\u0e19\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 123 2569-07-20 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0453569001080\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e31\u0e4b\u0e19-\u0e44\u0e2d\u0e27\u0e35\u0e48 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001080 \u0e2b\u0e08.\u0e2d\u0e31\u0e4b\u0e19-\u0e44\u0e2d\u0e27\u0e35\u0e48 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 2569-07-20 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 132  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0483569000539\",\"name_th\":\"\u0e2b\u0e08.\u0e1b.\u0e19\u0e32\u0e2b\u0e27\u0e49\u0e32 \u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47111\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47111\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000539 \u0e2b\u0e08.\u0e1b.\u0e19\u0e32\u0e2b\u0e27\u0e49\u0e32 \u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c 2569-07-20 1000000 47111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0503569005076\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e1e\u0e35 \u0e04\u0e25\u0e35\u0e19\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005076 \u0e2b\u0e08.\u0e0b\u0e35\u0e1e\u0e35 \u0e04\u0e25\u0e35\u0e19 2569-07-20 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e25\u0e35\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 150  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016274\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e14\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016274 \u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e14\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545\\\"\\\" \u88fd\u9020 377  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e18\u0e19\u0e32\u0e42\u0e0a\u0e04 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016291\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e25\u0e2d\u0e22\u0e02\u0e27\u0e31\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016291 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e25\u0e2d\u0e22\u0e02\u0e27\u0e31\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 82199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 58\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016304\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e04\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016304 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e04\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e04\u0e48\u0e32\u0e22\u0e21\u0e27\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e34\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e19 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 2\/1\/1  \u0e16\u0e19\u0e19\u0e2b\u0e32\u0e22\u0e22\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016339\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e47\u0e04\u0e2a\u0e17\u0e34\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47611\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47611\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016339 \u0e1a\u0e08.\u0e40\u0e14\u0e47\u0e04\u0e2a\u0e17\u0e34\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47611 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21 \u0e40\u0e25\u0e48\u0e21\u0e40\u0e01\u0e21 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2d\u0e27\u0e22\u0e1e\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 541  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e17\u0e23\u0e32\u0e22\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016355\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e19\u0e21\u0e41\u0e21\u0e48 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10792\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10792\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016355 \u0e1a\u0e08.\u0e02\u0e19\u0e21\u0e41\u0e21\u0e48 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 10792 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e44\u0e17\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u88fd\u9020 585  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016363\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e31\u0e21\u0e15\u0e33\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e1a\u0e32\u0e22\u0e40\u0e08\u0e49\u0e2d\u0e4b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016363 \u0e1a\u0e08.\u0e2a\u0e31\u0e21\u0e15\u0e33\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e1a\u0e32\u0e22\u0e40\u0e08\u0e49\u0e2d\u0e4b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 59\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001676\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e19\u0e32\u0e19\u0e32\u0e0b\u0e34\u0e25 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001676 \u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e19\u0e32\u0e19\u0e32\u0e0b\u0e34\u0e25 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46692 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e27\u0e31\u0e15\u0e16\u0e38\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e14\u0e34\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e21\u0e35 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e19\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e41\u0e25\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e25\u0e34\u0e48\u0e19\u0e40\u0e19\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e47\u0e19\u0e43\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e04\u0e2d\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0535569000793\",\"name_th\":\"\u0e1a\u0e08.\u0e2a 6299 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000793 \u0e1a\u0e08.\u0e2a 6299 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 309\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0565569000645\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u0e42\u0e2e\u0e21\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000645 \u0e1a\u0e08.\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\u0e42\u0e2e\u0e21\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 183  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e41\u0e21\u0e48\u0e2a\u0e38\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0565569000653\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e39\u0e0a\u0e39\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000653 \u0e1a\u0e08.\u0e0a\u0e39\u0e0a\u0e39\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e2a\u0e1c\u0e31\u0e14\u0e44\u0e17\u0e22 \u0e0b\u0e2d\u0e2a\u0e1c\u0e31\u0e14\u0e01\u0e23\u0e30\u0e40\u0e1e\u0e23\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0b\u0e2d\u0e2a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0603569001657\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e04\u0e2d\u0e34\u0e19\u0e19\u0e35\u0e15\u0e35\u0e49\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001657 \u0e2b\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e04\u0e2d\u0e34\u0e19\u0e19\u0e35\u0e15\u0e35\u0e49 2569-07-20 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0653569001151\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e2a\u0e2d\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001151 \u0e2b\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e1f \u0e2a\u0e2d\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 2569-07-20 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e17\u0e23\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30 \u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16 \u6559\u80b2 204\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0665569000709\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32\u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000709 \u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e0a\u0e32\u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0705569003260\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e30\u0e15\u0e4a\u0e32\u0e01\u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003260 \u0e1a\u0e08.\u0e01\u0e30\u0e15\u0e4a\u0e32\u0e01\u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 324  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003278\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a. \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003278 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a. \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 155\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003286\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003286 \u0e1a\u0e08.\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 11041 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 46\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007311\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81292\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81292\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007311 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 81292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 61\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007320\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d 9 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007320 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d 9 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e37\u0e0a \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07  \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007338\",\"name_th\":\"\u0e1a\u0e08.168 \u0e15\u0e49\u0e32\u0e2b\u0e25\u0e07 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007338 \u0e1a\u0e08.168 \u0e15\u0e49\u0e32\u0e2b\u0e25\u0e07 \u0e1e\u0e23\u0e34\u0e49\u0e19\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007346\",\"name_th\":\"\u0e1a\u0e08.999 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007346 \u0e1a\u0e08.999 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e27\u0e17\u0e4c\u0e2d\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 200\/64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007362\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35\u0e21\u0e35\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007362 \u0e1a\u0e08.\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35\u0e21\u0e35\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/232  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007371\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e07\u0e2d\u0e31\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007371 \u0e1a\u0e08.\u0e14\u0e31\u0e07\u0e2d\u0e31\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u533b\u7642\u30fb\u798f\u7949 40  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007389\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e40\u0e21\u0e40\u0e17\u0e35\u0e22 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11049\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11049\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007389 \u0e1a\u0e08.\u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e40\u0e21\u0e40\u0e17\u0e35\u0e22 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 11049 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e2d\u0e07\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e43\u0e19\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e34\u0e17 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e34\u0e17 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e2b\u0e49\u0e07  \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e43\u0e19\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e34\u0e17\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e2b\u0e49\u0e07 \u88fd\u9020 202\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0753569000102\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e1e\u0e35 \u0e40\u0e04 \u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e41\u0e1b\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0753569000102 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e1e\u0e35 \u0e40\u0e04 \u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e41\u0e1b\u0e14 2569-07-20 1000000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 ? \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e08\u0e30\u0e40\u0e01\u0e23\u0e47\u0e073 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0763569000323\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e21\u0e21\u0e35\u0e48 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0763569000323 \u0e2b\u0e08.\u0e0a\u0e21\u0e21\u0e35\u0e48 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 2569-07-20 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2b\u0e34\u0e49\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e01\u0e38\u0e0a\u0e0a\u0e35\u0e48 \u0e1b\u0e49\u0e2d\u0e1b\u0e21\u0e32\u0e17 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e02\u0e19\u0e21  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569003057\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e48\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003057 \u0e1a\u0e08.\u0e21\u0e35\u0e48\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 43210 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e25\u0e21 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e33 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1b\u0e25\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 424  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 13 \u0e16\u0e19\u0e19\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33\u0e1b\u0e23\u0e32\u0e13-\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569013345\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e34\u0e21\u0e34\u0e2a \u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"50212\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"50212\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013345 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e34\u0e21\u0e34\u0e2a \u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 50212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e40\u0e23\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e28\u0e19\u0e32\u0e08\u0e23\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e0a\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e23\u0e32\u0e0d\u0e01\u0e35\u0e2c\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e23\u0e37\u0e2d \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e01\u0e1b\u0e25\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 186\/73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013353\",\"name_th\":\"\u0e1a\u0e08. \u0e27\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e04\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013353 \u0e1a\u0e08. \u0e27\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e04\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47640 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010567\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010567 \u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 109\/55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0903569001719\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001719 \u0e2b\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-20 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e16\u0e19\u0e19\u0e16\u0e27\u0e34\u0e25\u0e1a\u0e39\u0e23\u0e13\u0e30 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005937\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2d\u0e01 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005937 \u0e1a\u0e08.\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e2d\u0e01 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 86202 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 , \u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e2d\u0e49\u0e27\u0e19 , \u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e40\u0e25\u0e47\u0e01 , \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e40\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e22\u0e35\u0e48\u0e22\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u533b\u7642\u30fb\u798f\u7949 632  \u0e16\u0e19\u0e19\u0e18\u0e23\u0e23\u0e21\u0e19\u0e39\u0e0d\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005953\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e0b\u0e39 \u0e40\u0e2d\u0e47\u0e19.\u0e41\u0e2d\u0e25.\u0e40\u0e2d\u0e1f \u0e40\u0e1b\u0e44\u0e15 \u0e44\u0e14\u0e25\u0e35\u0e48 \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005953 \u0e1a\u0e08.\u0e0b\u0e39\u0e0b\u0e39 \u0e40\u0e2d\u0e47\u0e19.\u0e41\u0e2d\u0e25.\u0e40\u0e2d\u0e1f \u0e40\u0e1b\u0e44\u0e15 \u0e44\u0e14\u0e25\u0e35\u0e48 \u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e2a\u0e27\u0e19\u0e04\u0e23\u0e31\u0e27 \u0e2a\u0e30\u0e15\u0e2d \u0e15\u0e30\u0e44\u0e04\u0e23\u0e49 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0945569000765\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000765 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 1000000 47113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0103569007731\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e08\u0e32\u0e01\u0e14\u0e34\u0e19 \u0e2d\u0e30\u0e42\u0e01\u0e23\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007731 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e08\u0e32\u0e01\u0e14\u0e34\u0e19 \u0e2d\u0e30\u0e42\u0e01\u0e23 2569-07-19 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 509\/314  \u0e0b\u0e2d\u0e22 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007749\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e27\u0e07\u0e17\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007749 \u0e2b\u0e08.\u0e23\u0e27\u0e07\u0e17\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-19 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 134  \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135943\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e31\u0e25 \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135943 \u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e31\u0e25 \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e16\u0e19\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e16\u0e21\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e17\u0e23\u0e32\u0e22 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e2b\u0e19\u0e49\u0e32\u0e14\u0e34\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e07\u0e32\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 388\/179  \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135951\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e41\u0e21\u0e01\u0e0b\u0e4c \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135951 \u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e41\u0e21\u0e01\u0e0b\u0e4c \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e40\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e21\u0e2b\u0e48\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22  \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e40\u0e40\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/61  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 19\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135978\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e2a\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135978 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e2a\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 80\/99  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e47\u0e0d\u0e1e\u0e23 \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 44 \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135986\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e01\u0e35\u0e49 \u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135986 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e01\u0e35\u0e49 \u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/16  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e222 \u0e0b\u0e2d\u0e2231 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135994\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e2b\u0e25\u0e34\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135994 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e2b\u0e25\u0e34\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1281\/2  \u0e16\u0e19\u0e19\u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136010\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e01\u0e23\u0e19\u0e14\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136010 \u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e01\u0e23\u0e19\u0e14\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u4e0d\u52d5\u7523 5\/7  \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023860\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023860 \u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e1e\u0e23\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 789  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023878\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e38\u0e29\u0e23\u0e32 \u0e02\u0e19\u0e2a\u0e48\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023878 \u0e1a\u0e08.\u0e19\u0e38\u0e29\u0e23\u0e32 \u0e02\u0e19\u0e2a\u0e48\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027245\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e33\u0e0a\u0e31\u0e22 \u0e23\u0e34\u0e0a \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027245 \u0e1a\u0e08.\u0e1e\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e33\u0e0a\u0e31\u0e22 \u0e23\u0e34\u0e0a \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a\u0e40\u0e01\u0e48\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0175569000487\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e32 1941 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000487 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e32 1941 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e42\u0e2d\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28  \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e27\u0e31\u0e07\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u91d1\u878d\u30fb\u4fdd\u967a 33  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2a\u0e32\u0e04\u0e23 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000809\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000809 \u0e2b\u0e08.\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 2569-07-19 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u5bbf\u6cca\u30fb\u98f2\u98df 129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037819\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e44\u0e0b\u0e17\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037819 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e44\u0e0b\u0e17\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 79110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 94\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007463\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e01\u0e48\u0e01\u0e30\u0e15\u0e4a\u0e32\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007463 \u0e1a\u0e08.\u0e44\u0e01\u0e48\u0e01\u0e30\u0e15\u0e4a\u0e32\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 231  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0395569000451\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e39\u0e40\u0e25\u0e14\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000451 \u0e1a\u0e08.\u0e17\u0e23\u0e39\u0e40\u0e25\u0e14\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 68\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e44\u0e2a\u0e22\u0e2d\u0e38\u0e14\u0e23\u0e01\u0e34\u0e08 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0405569006954\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006954 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 69200 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 468\/5  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e35\u0e42\u0e2d \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016266\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016266 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e1b\u0e25\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e27\u0e35\u0e0b\u0e48\u0e32 (visa) \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 (work permit) \u0e02\u0e2d\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 583  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e16\u0e49\u0e2d\u0e22\u0e19\u0e49\u0e33\u0e07\u0e32\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e19\u0e49\u0e33\u0e07\u0e32\u0e21 4 \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0713569000544\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19 168 \u0e1e\u0e25\u0e31\u0e2a\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0713569000544 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19 168 \u0e1e\u0e25\u0e31\u0e2a 2569-07-19 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e04\u0e23\u0e35\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0845569010559\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010559 \u0e1a\u0e08.\u0e1a\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 20\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569135625\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135625 \u0e1a\u0e08.\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 107  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135633\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23 2026 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135633 \u0e1a\u0e08.\u0e1e\u0e23\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23 2026 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 436  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e25\u0e33\u0e01\u0e2d\u0e44\u0e1c\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135650\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135650 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 341\/46  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e43\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135668\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e19. \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46431\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46431\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135668 \u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e19. \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46431 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 109\/66  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0b\u0e19\u0e42\u0e17\u0e23 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32109 \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c21 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135676\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e49\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135676 \u0e1a\u0e08.\u0e0a\u0e49\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 \u0e40\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 21\/83  \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135692\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e21\u0e32\u0e23\u0e4c\u0e17 129 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135692 \u0e1a\u0e08.\u0e23\u0e34\u0e0a\u0e21\u0e32\u0e23\u0e4c\u0e17 129 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2991\/9  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135706\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e32\u0e01\u0e04\u0e25\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135706 \u0e1a\u0e08.\u0e1b\u0e32\u0e01\u0e04\u0e25\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 68104 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e31\u0e14\u0e1a\u0e39\u0e18 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e15\u0e48\u0e32\u0e07 \u0e46 \u4e0d\u52d5\u7523 3  \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e01\u0e25\u0e32\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135714\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135714 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 43210 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 (smartbuilding) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 98\/189  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30\u0e04\u0e34\u0e27\u0e1a\u0e4c \u0e40\u0e0b\u0e32\u0e17\u0e4c \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 15\/1 \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 15\/1 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135722\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135722 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 (licensing) \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c (cloud computing) \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 123\/219  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135731\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135731 \u0e1a\u0e08.\u0e42\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 14  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 3 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135749\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e34\u0e14 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135749 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e34\u0e14 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 592\/212  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135757\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135757 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e0a\u0e33\u0e23\u0e38\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e2a\u0e20\u0e32\u0e1e \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u88fd\u9020 55  \u0e0b\u0e2d\u0e22 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c 1 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135790\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32\u0e27\u0e23\u0e23\u0e13 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135790 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32\u0e27\u0e23\u0e23\u0e13 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 (\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a,\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e44\u0e2d\u0e17\u0e35) \u60c5\u5831\u901a\u4fe1\u30fbit 119\/367  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e2115 (\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2d\u0e31\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e2f3\u0e1c\u0e31\u0e074) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135803\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e0a\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135803 \u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e0a\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 94  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 106 (\u0e1a\u0e38\u0e0d\u0e2d\u0e38\u0e14\u0e21 1) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135838\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e42\u0e23 \u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135838 \u0e1a\u0e08.\u0e44\u0e1e\u0e42\u0e23 \u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46691 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e01\u0e29\u0e23  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 5a-4 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135862\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e39\u0e21\u0e1a\u0e34\u0e4a\u0e01\u0e42\u0e19\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63990\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63990\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135862 \u0e1a\u0e08.\u0e1a\u0e39\u0e21\u0e1a\u0e34\u0e4a\u0e01\u0e42\u0e19\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 63990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49 ai \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 1  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e43\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135871\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e2d\u0e35\u0e17\u0e35 \u0e1e\u0e35\u0e2d\u0e35 \u0e40\u0e0b\u0e25\u0e1f\u0e4c \u0e2a\u0e15\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135871 \u0e1a\u0e08.\u0e08\u0e35\u0e2d\u0e35\u0e17\u0e35 \u0e1e\u0e35\u0e2d\u0e35 \u0e40\u0e0b\u0e25\u0e1f\u0e4c \u0e2a\u0e15\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 70202 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 388\/112  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e0b\u0e21\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e25\u0e39\u0e0b\u0e35\u0e1e \u0e04\u0e27\u0e35\u0e19\u0e2a\u0e4c \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e44\u0e1c\u0e48\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e42\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135889\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e2d\u0e35\u0e17\u0e35 \u0e1e\u0e35\u0e2d\u0e35 \u0e40\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135889 \u0e1a\u0e08.\u0e08\u0e35\u0e2d\u0e35\u0e17\u0e35 \u0e1e\u0e35\u0e2d\u0e35 \u0e40\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 388\/112  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e0b\u0e21\u0e34\u0e2a \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e25\u0e39\u0e0b\u0e35\u0e1e \u0e04\u0e27\u0e35\u0e19\u0e2a\u0e4c \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e44\u0e1c\u0e48\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e42\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135897\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e40\u0e21\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135897 \u0e1a\u0e08.\u0e0b\u0e2d\u0e23\u0e4c\u0e0b\u0e40\u0e21\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 322\/178  \u0e16\u0e19\u0e19\u0e2d\u0e42\u0e28\u0e01-\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135901\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e16\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135901 \u0e1a\u0e08.\u0e27\u0e34\u0e16\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 103\/28  \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135919\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135919 \u0e1a\u0e08.\u0e42\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e39\u0e49\u0e23\u0e1a \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e2d\u0e14\u0e34\u0e40\u0e23\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 48 \u0e41\u0e22\u0e01 17\/1 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135935\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e01\u0e49\u0e32\u0e22\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135935 \u0e1a\u0e08.\u0e2d\u0e2d\u0e01\u0e49\u0e32\u0e22\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e35\u0e2c\u0e32\u0e22\u0e34\u0e21\u0e19\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e01\u0e32\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e22\u0e04\u0e30 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19\u0e23\u0e33 \u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e14\u0e47\u0e01 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u6559\u80b2 289\/240  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 6\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023801\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e14\u0e22\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"88901\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"88901\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023801 \u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e14\u0e22\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 88901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e47\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e23\u0e34\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e14\u0e47\u0e01\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u533b\u7642\u30fb\u798f\u7949 100\/10  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e39\u0e21\u0e34\u0e2a\u0e34\u0e23\u0e34 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e14\u0e48\u0e32\u0e19 22 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023819\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e32\u0e07\u0e40\u0e2b\u0e27\u0e48\u0e22\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e1b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023819 \u0e1a\u0e08.\u0e09\u0e32\u0e07\u0e40\u0e2b\u0e27\u0e48\u0e22\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e1b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32\u0e41\u0e2b\u0e49\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32\u0e17\u0e2d\u0e14 \u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32\u0e2a\u0e14 \u0e1b\u0e25\u0e32\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 280\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023827\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e1a\u0e32\u0e19\u0e32\u0e19\u0e48\u0e32\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023827 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e1a\u0e32\u0e19\u0e32\u0e19\u0e48\u0e32\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence : ai) \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (automation) \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 307\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027199\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e23\u0e34\u0e19 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027199 \u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e23\u0e34\u0e19 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 28\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027202\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e0c\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027202 \u0e1a\u0e08.\u0e18\u0e32\u0e0c\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 (event organizer) \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/84  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e24\u0e29\u0e15\u0e34\u0e22\u0e323 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027211\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e21 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027211 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e21 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 50\/413  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022090\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10502\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10502\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022090 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 10502 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e08\u0e37\u0e2d\u0e1b\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e21\u0e42\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e43\u0e19\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e34\u0e17\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e19\u0e21\u0e1c\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 333\/156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022120\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e41\u0e0b\u0e1424 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022120 \u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e41\u0e0b\u0e1424 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19 \u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e2a (e-commerce) \u0e41\u0e25\u0e30 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e40\u0e1e\u0e25\u0e2a (marketplace) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022138\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022138 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/488  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e27\u0e19\u0e17\u0e2d\u0e07\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 7 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 11 \u0e16\u0e19\u0e19\u0e44\u0e2a\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022162\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e41\u0e0b\u0e1424 \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022162 \u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e41\u0e0b\u0e1424 \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07  \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15  \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\\\"\\\" \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0165569001653\",\"name_th\":\"\u0e1a\u0e08.\u0e1b.\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e38\u0e12\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001653 \u0e1a\u0e08.\u0e1b.\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e38\u0e12\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037711\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e08\u0e19\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037711 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e08\u0e19\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e27\u0e14\u0e27\u0e34\u0e0a\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u6559\u80b2 80\/206  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037720\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e1e\u0e0a\u0e23 \u0e40\u0e04\u0e35\u0e22\u0e23\u0e4c\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38110\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38110\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037720 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e1e\u0e0a\u0e23 \u0e40\u0e04\u0e35\u0e22\u0e23\u0e4c\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 38110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e01\u0e32\u0e01\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 (\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25) \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e28\u0e29\u0e42\u0e25\u0e2b\u0e30  \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 48\/16  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e13\u0e35\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e44\u0e1e\u0e23\u0e40\u0e27\u0e0b\u0e35\u0e48 \u0e21\u0e34\u0e15\u0e23\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037738\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037738 \u0e1a\u0e08.\u0e23\u0e27\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 68104 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c,\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 297\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037746\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47999\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47999\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037746 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e33 \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 242\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037754\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e0d\u0e20\u0e31\u0e17\u0e23 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037754 \u0e1a\u0e08.\u0e0a\u0e32\u0e0d\u0e20\u0e31\u0e17\u0e23 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 66\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037762\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e1e\u0e23\u0e4a\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037762 \u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e1e\u0e23\u0e4a\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e0d\u52d5\u7523 115\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037771\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037771 \u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e21\u0e39,\u0e44\u0e01\u0e48,\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a,\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23,\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07,\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07,\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037797\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0b\u0e31\u0e1e\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28230\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28230\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037797 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0b\u0e31\u0e1e\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 28230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e41\u0e25\u0e30\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01 \u88fd\u9020 388  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009556\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e40\u0e1f\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009556 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e40\u0e1f\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 199\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0305569007455\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19\u0e0b\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007455 \u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19\u0e0b\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 298\/25  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001081\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35\u0e08\u0e31\u0e07\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001081 \u0e2b\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35\u0e08\u0e31\u0e07 2569-07-18 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 213  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0335569001155\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e08\u0e19\u0e30\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25(2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001155 \u0e1a\u0e08.\u0e42\u0e23\u0e08\u0e19\u0e30\u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25(2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e32\u0e01\u0e40\u0e02\u0e35\u0e22\u0e1a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0365569001457\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e27\u0e22\u0e2a\u0e21\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001457 \u0e1a\u0e08.\u0e2d\u0e27\u0e22\u0e2a\u0e21\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 158  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0405569006946\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006946 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22  \u0e40\u0e0a\u0e48\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 204  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003769\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e44\u0e18\u0e2a\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003769 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e44\u0e18\u0e2a\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49 \u0e41\u0e01\u0e48\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e32\u0e02\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01. \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02. \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e04. \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e07. \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08. \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e09. \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e0a. \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e0b. \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e0c. \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000865\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e35\u0e41\u0e0b\u0e17 \u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000865 \u0e2b\u0e08.\u0e2d\u0e35\u0e41\u0e0b\u0e17 \u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-18 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 407\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0503569005033\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2026\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005033 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2026 2569-07-18 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 288\/49  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e2d\u0e25\u0e34\u0e19 \u0e2a\u0e31\u0e19\u0e17\u0e23\u0e32\u0e22 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016223\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e2a\u0e30 \u0e2d\u0e30\u0e40\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016223 \u0e1a\u0e08.\u0e2d\u0e30\u0e2a\u0e30 \u0e2d\u0e30\u0e40\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 174  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016231\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e32 \u0e2d\u0e2d\u0e1f \u0e14\u0e34 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016231 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e32 \u0e2d\u0e2d\u0e1f \u0e14\u0e34 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 (workshop) \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e04\u0e48\u0e32\u0e22 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e27\u0e30 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e22 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u6559\u80b2 168\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016240\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e42\u0e13\u0e17\u0e31\u0e22\u0e23\u0e31\u0e15\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016240 \u0e1a\u0e08.\u0e2d\u0e42\u0e13\u0e17\u0e31\u0e22\u0e23\u0e31\u0e15\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e19 \u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 333\/39  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e2a\u0e34\u0e23\u0e34 \u0e2a\u0e31\u0e19\u0e17\u0e23\u0e32\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 9 \u0e16\u0e19\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48-\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004659\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e25\u0e27\u0e4c\u0e04\u0e2d\u0e23\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004659 \u0e1a\u0e08.\u0e42\u0e1f\u0e25\u0e27\u0e4c\u0e04\u0e2d\u0e23\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e41\u0e14\u0e0a\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u60c5\u5831\u901a\u4fe1\u30fbit 178  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004667\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e1e\u0e23\u0e30\u0e1e\u0e23 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004667 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e1e\u0e23\u0e30\u0e1e\u0e23 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46318 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e01\u0e30\u0e25\u0e32 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e32\u0e23 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27 \u0e01\u0e32\u0e41\u0e1f\u0e1a\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 472\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004675\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004675 \u0e1a\u0e08.\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569002132\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e0a\u0e38\u0e15\u0e34\u0e21\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002132 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e0a\u0e38\u0e15\u0e34\u0e21\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 1\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002159\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002159 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e2a\u0e31\u0e19\u0e04\u0e39-\u0e27\u0e31\u0e07\u0e44\u0e1c\u0e48 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0735569007281\",\"name_th\":\"\u0e1a\u0e08.\u0e10\u0e21\u0e17\u0e2d\u0e07 88 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007281 \u0e1a\u0e08.\u0e10\u0e21\u0e17\u0e2d\u0e07 88 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e21\u0e39\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007303\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e48\u0e32 \u0e27\u0e31\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007303 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e48\u0e32 \u0e27\u0e31\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 47912 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 159\/171  \u0e16\u0e19\u0e19\u0e22\u0e34\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e43\u0e15\u0e49 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0743569001028\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e23\u0e31\u0e0d\u0e0d\u0e32 \u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569001028 \u0e2b\u0e08.\u0e2d\u0e23\u0e31\u0e0d\u0e0d\u0e32 \u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-18 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 1092\/211  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e42\u0e0a\u0e0e\u0e01 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0743569001036\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e38\u0e49\u0e07\u0e2a\u0e14 \u0e42\u0e19.1 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569001036 \u0e2b\u0e08.\u0e01\u0e38\u0e49\u0e07\u0e2a\u0e14 \u0e42\u0e19.1 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 2569-07-18 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 72\/94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007613\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007613 \u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e02\u0e2d\u0e07\u0e0a\u0e4d\u0e32\u0e23\u0e48\u0e27\u0e22 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1f \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e01\u0e49\u0e27\u0e19\u0e4d\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e25\u0e42\u0e01\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0805569002769\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002769 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev station) \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 168\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0865569001266\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35.\u0e40\u0e27\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001266 \u0e1a\u0e08.\u0e1a\u0e35.\u0e40\u0e27\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 180\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e21\u0e34\u0e19\u0e17\u0e23\u0e21\u0e23\u0e23\u0e04\u0e32 29 \u0e16\u0e19\u0e19\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001662\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e28\u0e23\u0e32\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e32\u0e19\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46499\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46499\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001662 \u0e2b\u0e08.\u0e40\u0e01\u0e28\u0e23\u0e32\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e32\u0e19 2569-07-18 1000000 46499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e37\u0e19 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e31\u0e01\u0e2a\u0e32\u0e19\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e15\u0e49\u0e19\u0e01\u0e23\u0e30\u0e08\u0e39\u0e14 \u0e15\u0e49\u0e19\u0e01\u0e01 \u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 \u0e44\u0e1c\u0e48 \u0e41\u0e25\u0e30\u0e2b\u0e27\u0e32\u0e22 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e32\u0e19 \u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e23\u0e30\u0e08\u0e39\u0e14 \u0e15\u0e30\u0e01\u0e23\u0e49\u0e32\u0e2a\u0e32\u0e19  \u0e2b\u0e21\u0e27\u0e01\u0e2a\u0e32\u0e19 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001671\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e2d\u0e21\u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e17\u0e2d\u0e07\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001671 \u0e2b\u0e08.\u0e2d\u0e2d\u0e21\u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e17\u0e2d\u0e07 2569-07-18 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d\u0e04\u0e37\u0e19 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07 \u0e17\u0e2d\u0e07\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e21\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e01\u0e32\u0e23\u0e2a\u0e30\u0e2a\u0e21\u0e22\u0e2d\u0e14\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e2d\u0e07\u0e04\u0e33  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e21\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001689\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e08\u0e34\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e07\u0e2a\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001689 \u0e2b\u0e08.\u0e2a\u0e38\u0e08\u0e34\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e07\u0e2a\u0e14 2569-07-18 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e07\u0e2a\u0e14 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e07\u0e02\u0e49\u0e19  \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e23\u0e21\u0e04\u0e27\u0e31\u0e19 \u0e22\u0e32\u0e07\u0e41\u0e17\u0e48\u0e07 \u0e22\u0e32\u0e07\u0e40\u0e04\u0e23\u0e1b \u0e02\u0e35\u0e49\u0e22\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e02\u0e31\u0e49\u0e19\u0e15\u0e49\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001697\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e1f\u0e49\u0e32\u0e04\u0e2d\u0e21\u0e40\u0e17\u0e04\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001697 \u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e1f\u0e49\u0e32\u0e04\u0e2d\u0e21\u0e40\u0e17\u0e04 2569-07-18 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 (\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d) \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007641\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e22\u0e19\u0e15\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007641 \u0e2b\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e22\u0e19\u0e15\u0e4c 2569-07-17 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 509\/314  \u0e0b\u0e2d\u0e22 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007650\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007650 \u0e2b\u0e08.\u0e1e\u0e35\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 2569-07-17 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 509\/31  \u0e0b\u0e2d\u0e22 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007668\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e34\u0e23\u0e34 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007668 \u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e34\u0e23\u0e34 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 2569-07-17 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 111  \u0e0b\u0e2d\u0e22 \u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 4 \u0e16\u0e19\u0e19\u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007684\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e31\u0e01\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e1e\u0e23\u0e32\u0e27\u0e14\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007684 \u0e2b\u0e08.\u0e25\u0e31\u0e01\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e1e\u0e23\u0e32\u0e27\u0e14\u0e4c 2569-07-17 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 388\/34  \u0e16\u0e19\u0e19\u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007692\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e18\u0e35\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007692 \u0e2b\u0e08.\u0e19\u0e18\u0e35\u0e23\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 2569-07-17 1000000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e1a\u0e31\u0e2a \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 104  \u0e0b\u0e2d\u0e22 \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007714\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e31\u0e27 \u0e0b\u0e35\u0e23\u0e47\u0e2d\u0e01\u0e0b\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82191\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82191\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007714 \u0e2b\u0e08.\u0e1a\u0e31\u0e27 \u0e0b\u0e35\u0e23\u0e47\u0e2d\u0e01\u0e0b\u0e4c 2569-07-17 1000000 82191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b  \u0e25\u0e49\u0e32\u0e07  \u0e2d\u0e31\u0e14  \u0e02\u0e22\u0e32\u0e22\u0e23\u0e39\u0e1b  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 295  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e25\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134947\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d \u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134947 \u0e1a\u0e08.\u0e42\u0e2d \u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23(full service marketing and talent management agency) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 600\/56  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e35\u0e41\u0e2a\u0e04\u0e27\u0e23\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e219 \u0e40\u0e2b\u0e21\u0e48\u0e07\u0e08\u0e4b\u0e32\u0e22 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0739 (\u0e40\u0e17\u0e1e\u0e25\u0e35\u0e25\u0e321) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134955\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a\u0e2a \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134955 \u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a\u0e2a \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22\u0e2a\u0e35\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c (ppf) \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 309\/1  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134963\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e23\u0e2d\u0e14\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134963 \u0e1a\u0e08.\u0e1a\u0e23\u0e2d\u0e14\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data analytics) \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25  (data processing) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e20\u0e32\u0e04\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u60c5\u5831\u901a\u4fe1\u30fbit 300\/71  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134998\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e158 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134998 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e158 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e04\u0e23\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e23\u0e31\u0e27\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e38\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74\/9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07\u0e40\u0e1e\u0e25\u0e2a \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135005\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135005 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e37\u0e48\u0e2d \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/190  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135021\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e38\u0e07\u0e2a\u0e49\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135021 \u0e1a\u0e08.\u0e25\u0e38\u0e07\u0e2a\u0e49\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 82990 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 59\/2-3-4  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 42 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135056\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e15\u0e31\u0e1f\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135056 \u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e15\u0e31\u0e1f\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19 \u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e1a\u0e34\u0e19 \u0e25\u0e39\u0e01\u0e40\u0e23\u0e37\u0e2d \u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 512  \u0e0b\u0e2d\u0e22 \u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135064\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e21\u0e34\u0e2a \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135064 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e21\u0e34\u0e2a \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e04\u0e39\u0e48 \u0e2a\u0e23\u0e23\u0e2b\u0e32 \u0e19\u0e31\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e20\u0e32\u0e1e \u0e0a\u0e48\u0e32\u0e07\u0e20\u0e32\u0e1e\u0e2d\u0e34\u0e2a\u0e23\u0e30 \u0e19\u0e32\u0e07\u0e41\u0e1a\u0e1a \u0e19\u0e32\u0e22\u0e41\u0e1a\u0e1a \u0e0a\u0e48\u0e32\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32 \u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c) \u60c5\u5831\u901a\u4fe1\u30fbit 69\/103  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e34\u0e48\u0e21\u0e2d\u0e33\u0e1e\u0e232 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c9 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135102\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e25\u0e25\u0e35\u0e27\u0e39\u0e14 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135102 \u0e1a\u0e08.\u0e1a\u0e2d\u0e25\u0e25\u0e35\u0e27\u0e39\u0e14 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e15\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e15\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 110  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e04 \u0e27\u0e32\u0e22  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 6 \u0e0b\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e32\u0e42\u0e21\u0e17\u0e22\u0e4c 3 \u0e16\u0e19\u0e19\u0e21\u0e40\u0e2b\u0e2a\u0e31\u0e01\u0e02\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135226\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e23\u0e27\u0e07\u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135226 \u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e23\u0e27\u0e07\u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e02\u0e49\u0e32\u0e27\u0e01\u0e25\u0e49\u0e2d\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e23\u0e33 \u0e1b\u0e25\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27 \u0e41\u0e01\u0e25\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23 \u0e2a\u0e35\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1469  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135234\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1a\u0e22\u0e4c\u0e0a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135234 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1a\u0e22\u0e4c\u0e0a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 21  \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e2a\u0e38\u0e01\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135242\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e40\u0e25\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135242 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e40\u0e25\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 14 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135277\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135277 \u0e1a\u0e08.\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u6559\u80b2 99\/170  \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135293\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e23\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2d\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47741\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47741\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135293 \u0e1a\u0e08.\u0e41\u0e23\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e2d\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47741 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 442-443 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e16\u0e19\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135315\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135315 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 29\/31  \u0e0b\u0e2d\u0e22 \u0e15\u0e49\u0e19\u0e44\u0e17\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135358\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e34\u0e19\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135358 \u0e1a\u0e08.\u0e04\u0e27\u0e34\u0e19\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 16-18  \u0e16\u0e19\u0e19\u0e1a\u0e38\u0e0d\u0e28\u0e34\u0e23\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135366\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135366 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e04\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e15\u0e48\u0e2d \u0e02\u0e49\u0e2d\u0e07\u0e2d \u0e2a\u0e32\u0e21\u0e17\u0e32\u0e07 \u0e27\u0e32\u0e25\u0e4c\u0e27 \u0e0b\u0e35\u0e25\u0e22\u0e32\u0e07 \u0e2b\u0e19\u0e49\u0e32\u0e41\u0e1b\u0e25\u0e19 \u0e41\u0e04\u0e25\u0e21\u0e1b\u0e4c \u0e17\u0e48\u0e2d\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/19  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135382\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e0a\u0e31\u0e22 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135382 \u0e1a\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e0a\u0e31\u0e22 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 56101 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e17\u0e23\u0e15\u0e32\u0e04\u0e32\u0e23\/\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 694  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135391\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e21\u0e15 \u0e14\u0e34\u0e2a\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135391 \u0e1a\u0e08.\u0e2d\u0e21\u0e15 \u0e14\u0e34\u0e2a\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 72102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 61  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 55 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135412\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135412 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 301  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 101 (\u0e27\u0e31\u0e14\u0e1a\u0e36\u0e07\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e32\u0e07) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135439\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e17\u0e35 \u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e19\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135439 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e17\u0e35 \u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e19\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 153  \u0e16\u0e19\u0e19\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135447\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e1e\u0e15\u0e34\u0e44\u0e21\u0e0b\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58201\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58201\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135447 \u0e1a\u0e08.\u0e2d\u0e2d\u0e1e\u0e15\u0e34\u0e44\u0e21\u0e0b\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 58201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e1c\u0e48\u0e19\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e01\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 5\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e24\u0e17\u0e18\u0e34\u0e4c\u0e23\u0e31\u0e15\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 6501 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135463\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e1e\u0e2d\u0e25\u0e42\u0e25 \u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135463 \u0e1a\u0e08.\u0e2d\u0e1e\u0e2d\u0e25\u0e42\u0e25 \u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 319  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e15\u0e38\u0e23\u0e31\u0e2a\u0e08\u0e32\u0e21\u0e08\u0e38\u0e23\u0e35  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1704 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135480\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135480 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45302 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e17\u0e44\u0e1f             \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157  \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135510\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e27\u0e34\u0e2a\u0e42\u0e01 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46614\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46614\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135510 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e27\u0e34\u0e2a\u0e42\u0e01 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46614 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7  \u0e0b\u0e2d\u0e22 \u0e41\u0e1e\u0e23\u0e48\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135536\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63912\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63912\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135536 \u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 63912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e15\u0e48\u0e2d\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e0a\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 21\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e34\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 610 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135544\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e40\u0e21\u0e14 \u0e41\u0e2d\u0e2a\u0e0b\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135544 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e40\u0e21\u0e14 \u0e41\u0e2d\u0e2a\u0e0b\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 96309 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e04\u0e19\u0e44\u0e02\u0e49\u0e43\u0e2b\u0e49\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 25\/9  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e43\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135579\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e34\u0e49\u0e19\u0e15\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135579 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e34\u0e49\u0e19\u0e15\u0e4c \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e19\u0e32\u0e21\u0e1e\u0e34\u0e04\u0e40\u0e04\u0e34\u0e25\u0e1a\u0e2d\u0e25 (pickleball) \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e43\u0e19\u0e23\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 10\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135587\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e19\u0e35 \u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e40\u0e2d\u0e47\u0e21\u0e44\u0e1e\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135587 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e19\u0e35 \u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e40\u0e2d\u0e47\u0e21\u0e44\u0e1e\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e19\u0e49\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/335  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135595\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135595 \u0e1a\u0e08.\u0e2a\u0e38\u0e02 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e01\u0e32\u0e23\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e22\u0e37\u0e19\u0e22\u0e32\u0e27 (longevity) \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u533b\u7642\u30fb\u798f\u7949 39  \u0e0b\u0e2d\u0e22 \u0e40\u0e22\u0e47\u0e19\u0e08\u0e34\u0e15 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135609\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e21. \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135609 \u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e21. \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5efa\u8a2d 8\/111  \u0e0b\u0e2d\u0e22 \u0e2a\u0e27\u0e19\u0e2a\u0e22\u0e32\u0e21 9 \u0e41\u0e22\u0e01 14 (\u0e2d\u0e21\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e19\u0e04\u0e23 8) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002551\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002551 \u0e2b\u0e08.\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 2569-07-17 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002569\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002569 \u0e2b\u0e08.\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c 2569-07-17 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 18\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023614\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e40\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e17\u0e39 \u0e42\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023614 \u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e40\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e17\u0e39 \u0e42\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e2a\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e01\u0e38\u0e25\u0e40\u0e07\u0e34\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 123\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e16\u0e19\u0e19\u0e01\u0e34\u0e48\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023649\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e25\u0e32\u0e1e\u0e34\u0e2a\u0e34\u0e10 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023649 \u0e1a\u0e08.\u0e0a\u0e32\u0e25\u0e32\u0e1e\u0e34\u0e2a\u0e34\u0e10 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 458\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023665\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e25\u0e34\u0e07\u0e01\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023665 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e25\u0e34\u0e07\u0e01\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 222\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023703\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e4a\u0e01 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023703 \u0e1a\u0e08.\u0e1a\u0e34\u0e4a\u0e01 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 3999\/98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023738\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023738 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 456\/78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023762\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e2d\u0e34\u0e21\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023762 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e2d\u0e34\u0e21\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023789\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023789 \u0e1a\u0e08.\u0e21\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 56\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002224\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e17\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002224 \u0e2b\u0e08.\u0e40\u0e08\u0e17\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0a\u0e47\u0e2d\u0e1b 2569-07-17 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c) \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027008\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e21\u0e07\u0e04\u0e25894  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027008 \u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e21\u0e07\u0e04\u0e25894  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 62\/94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027032\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e2a \u0e25\u0e2d\u0e27\u0e4c \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027032 \u0e1a\u0e08.\u0e27\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e35 \u0e42\u0e1b\u0e23\u0e40\u0e1f\u0e2a \u0e25\u0e2d\u0e27\u0e4c \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 98\/65  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e4c\u0e25\u0e14\u0e32 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027041\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e25\u0e34\u0e21\u0e34\u0e15 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027041 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e25\u0e34\u0e21\u0e34\u0e15 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e40\u0e0a\u0e48\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e1a\u0e35\u0e48\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e07\u0e32\u0e19\u0e17\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e07\u0e32\u0e19\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14      (21 ) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e42\u0e14\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e17\u0e32\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e37\u0e1a\u0e04\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 123\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027059\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02 \u0e23\u0e27\u0e22\u0e23\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027059 \u0e1a\u0e08.\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02 \u0e23\u0e27\u0e22\u0e23\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 47\/1  \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c 37 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027083\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027083 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027091\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e2a\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027091 \u0e1a\u0e08.\u0e44\u0e27\u0e2a\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e41\u0e19\u0e30\u0e19\u0e4d\u0e32\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e14\u0e49\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e42\u0e22\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 63\/59  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30-\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027105\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e0b\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10772\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10772\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027105 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e0b\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 10772 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 3\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e15\u0e49\u0e19\u0e2a\u0e19 13 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027113\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e35 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74902\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74902\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027113 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e2d\u0e35 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 74902 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e21 \u0e14\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c (franchise) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021964\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e1f \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021964 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e1f \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 261\/579  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e07\u0e42\u0e04\u0e0b\u0e35\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021981\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e49\u0e32\u0e19\u0e1c\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021981 \u0e1a\u0e08.\u0e25\u0e49\u0e32\u0e19\u0e1c\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/1376  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32 b \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 8 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022006\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e04\u0e14\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022006 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e04\u0e14\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 64201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022014\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e42\u0e04\u0e49\u0e27\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022014 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e42\u0e04\u0e49\u0e27\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21 \u0e40\u0e04\u0e32\u0e30\u0e1e\u0e48\u0e19\u0e2a\u0e35\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/320  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1f\u0e49\u0e32\u0e01\u0e23\u0e35\u0e19\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15\u0e04\u0e25\u0e2d\u0e07 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022022\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022022 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e31\u0e49\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e04\u0e48\u0e32\u0e22\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19  \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e04\u0e48\u0e32\u0e22\u0e22\u0e38\u0e42\u0e23\u0e1b  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 (hybrid)  \u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2d\u0e23\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022031\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e42\u0e22\u0e18\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022031 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e42\u0e22\u0e18\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 40\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022049\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022049 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u88fd\u9020 88\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022057\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08-\u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e42\u0e04\u0e49\u0e0a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85492\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85492\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022057 \u0e1a\u0e08.\u0e40\u0e08-\u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e42\u0e04\u0e49\u0e0a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 85492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u6559\u80b2 711\/235  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022065\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e17\u0e34\u0e40\u0e21\u0e17 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022065 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e17\u0e34\u0e40\u0e21\u0e17 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022073\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e2d\u0e18 \u0e21\u0e2d\u0e25\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"03225\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"03225\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022073 \u0e1a\u0e08.\u0e08\u0e2d\u0e18 \u0e21\u0e2d\u0e25\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 03225 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e2d\u0e19\u0e38\u0e1a\u0e32\u0e25 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e1b\u0e25\u0e32\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 (\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32\u0e1a\u0e2d\u0e25\u0e25\u0e39\u0e19) \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e23\u0e13\u0e44\u0e21\u0e49\u0e19\u0e49\u0e33 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u8fb2\u6797\u6c34\u7523 1369  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004717\",\"name_th\":\"\u0e1a\u0e08.\u0e1c\u0e48\u0e2d\u0e07\u0e1e\u0e23\u0e23\u0e13 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004717 \u0e1a\u0e08.\u0e1c\u0e48\u0e2d\u0e07\u0e1e\u0e23\u0e23\u0e13 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 56101 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23\/\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 67\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004725\",\"name_th\":\"\u0e1a\u0e08.\u0e28.\u0e21\u0e07\u0e04\u0e25 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004725 \u0e1a\u0e08.\u0e28.\u0e21\u0e07\u0e04\u0e25 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45302 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/13-15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0195569002633\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e15\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002633 \u0e1a\u0e08.\u0e0a\u0e34\u0e15\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 30\/4  \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003157\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e31\u0e14\u0e14\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e1a\u0e1b\u0e30\u0e23\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003157 \u0e2b\u0e08.\u0e25\u0e31\u0e14\u0e14\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e1a\u0e1b\u0e30\u0e23\u0e14 2569-07-17 1000000 47213 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e08\u0e33\u0e1e\u0e27\u0e01 \u0e2a\u0e31\u0e1a\u0e1b\u0e30\u0e23\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 418\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037533\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e09\u0e34\u0e19 \u0e0b\u0e34\u0e19 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17020\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17020\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037533 \u0e1a\u0e08.\u0e40\u0e09\u0e34\u0e19 \u0e0b\u0e34\u0e19 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 17020 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 134\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037541\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e23\u0e31\u0e0a\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037541 \u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e23\u0e31\u0e0a\u0e0a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e1a\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e35\u0e08\u0e23\u0e32\u0e08\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 301\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037576\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 782 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037576 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 782 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e14\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u4e0d\u52d5\u7523 48\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037584\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e19\u0e30 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037584 \u0e1a\u0e08.\u0e2e\u0e32\u0e19\u0e30 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037631\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037631 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037665\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e34\u0e07\u0e40\u0e1f\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037665 \u0e1a\u0e08.\u0e15\u0e34\u0e07\u0e40\u0e1f\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 307\/120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037681\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04 \u0e27\u0e2d\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037681 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04 \u0e27\u0e2d\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 11041 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e41\u0e23\u0e48\u0e2d\u0e31\u0e14\u0e25\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e34\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e34\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u88fd\u9020 233\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037690\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037690 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037703\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e02\u0e32\u0e22\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46415\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46415\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037703 \u0e1a\u0e08.\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e02\u0e32\u0e22\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46415 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 209\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009521\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e23\u0e34\u0e01\u0e32 \u0e40\u0e1a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009521 \u0e1a\u0e08.\u0e14\u0e32\u0e23\u0e34\u0e01\u0e32 \u0e40\u0e1a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19 (bakery) \u0e02\u0e19\u0e21\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u88fd\u9020 95\/13  \u0e0b\u0e2d\u0e22 \u0e40\u0e19\u0e34\u0e19\u0e1e\u0e23\u0e30 5 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e2d\u0e01\u0e22\u0e32\u0e22\u0e0a\u0e32 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009530\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e17\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009530 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e17\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 10\/57  \u0e0b\u0e2d\u0e22 \u0e40\u0e19\u0e34\u0e19\u0e1e\u0e23\u0e30 2 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e2d\u0e01\u0e22\u0e32\u0e22\u0e0a\u0e32 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002276\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e4c\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002276 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e4c\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (holding company) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u91d1\u878d\u30fb\u4fdd\u967a 54\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002284\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002284 \u0e1a\u0e08.\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e25\u0e33\u0e44\u0e22 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e31\u0e1b\u0e1b\u0e30\u0e23\u0e14 \u0e41\u0e2d\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e2a\u0e49\u0e21 \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e41\u0e01\u0e49\u0e27\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e01\u0e25\u0e49\u0e27\u0e22 \u0e01\u0e23\u0e30\u0e17\u0e49\u0e2d\u0e19 \u0e41\u0e15\u0e07\u0e42\u0e21 \u0e21\u0e30\u0e21\u0e48\u0e27\u0e07 \u0e01\u0e35\u0e27\u0e35\u0e48 \u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e2a\u0e15\u0e2d\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e40\u0e07\u0e32\u0e30 \u0e17\u0e31\u0e1a\u0e17\u0e34\u0e21 \u0e25\u0e2d\u0e07\u0e01\u0e2d\u0e07 \u0e25\u0e32\u0e07\u0e2a\u0e32\u0e14 \u0e2a\u0e25\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 230\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0235569000419\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e15\u0e4b\u0e40\u0e15\u0e4b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0235569000419 \u0e1a\u0e08.\u0e42\u0e15\u0e4b\u0e40\u0e15\u0e4b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e25\u0e33\u0e44\u0e22 \u0e21\u0e30\u0e02\u0e32\u0e21 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e21\u0e31\u0e19\u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e31\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e1c\u0e31\u0e01\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 182  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0245569003884\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003884 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e25\u0e36\u0e07 \u0e07\u0e32\u0e19\u0e01\u0e31\u0e14 \u0e07\u0e32\u0e19\u0e44\u0e2a \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 (machining) \u88fd\u9020 40\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003892\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e0a\u0e10\u0e32 \u0e1a\u0e32\u0e07\u0e19\u0e49\u0e33\u0e40\u0e1b\u0e23\u0e35\u0e49\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003892 \u0e1a\u0e08.\u0e25\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e0a\u0e10\u0e32 \u0e1a\u0e32\u0e07\u0e19\u0e49\u0e33\u0e40\u0e1b\u0e23\u0e35\u0e49\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1c\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e40\u0e21\u0e17\u0e31\u0e25\u0e0a\u0e35\u0e17 \u0e42\u0e04\u0e23\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e23\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003906\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e49\u0e2a\u0e34\u0e49\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003906 \u0e1a\u0e08.\u0e08\u0e39\u0e49\u0e2a\u0e34\u0e49\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 1\/304  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569007412\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007412 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 22299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 132\/363  \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e-\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007421\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e34\u0e18 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007421 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e34\u0e18 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105\/166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007439\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 1983 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007439 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 1983 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 999\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007447\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21-\u0e44\u0e25\u0e19\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007447 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21-\u0e44\u0e25\u0e19\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e48\u0e32\u0e19\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23  \u0e01\u0e32\u0e23\u0e0a\u0e33\u0e23\u0e30\u0e2d\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 74\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001064\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e20\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001064 \u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e20\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-17 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0313569001072\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e14\u0e32\u0e23\u0e32\u0e09\u0e32\u0e22\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001072 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e14\u0e32\u0e23\u0e32\u0e09\u0e32\u0e22 2569-07-17 1000000 46204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e01\u0e48\u0e0a\u0e19 \u0e40\u0e1e\u0e32\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e01\u0e48\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e01\u0e48\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569001945\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001945 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e33\u0e2a\u0e35 \u0e40\u0e04\u0e32\u0e30 \u0e1b\u0e30 \u0e1c\u0e38 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 333  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0343569001943\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e23\u0e38\u0e15\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001943 \u0e2b\u0e08.\u0e28\u0e23\u0e38\u0e15\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-17 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 8  \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e2a\u0e19\u0e34\u0e17 4\/7 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e2a\u0e19\u0e34\u0e17 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003247\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35 \u0e40\u0e04 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e0a\u0e47\u0e2d\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003247 \u0e1a\u0e08.\u0e0b\u0e35 \u0e40\u0e04 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e0a\u0e47\u0e2d\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 207  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003255\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e13\u0e13\u0e17\u0e31\u0e15\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003255 \u0e1a\u0e08.\u0e1b\u0e31\u0e13\u0e13\u0e17\u0e31\u0e15\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23 \u8fb2\u6797\u6c34\u7523 131-133  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e1e\u0e32\u0e01\u0e22\u0e4c \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003263\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e44\u0e1e\u0e25\u0e34\u0e19 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003263 \u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e44\u0e1e\u0e25\u0e34\u0e19 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 77101 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 157  \u0e16\u0e19\u0e19\u0e1c\u0e32\u0e41\u0e14\u0e07 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0385569000493\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e20\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000493 \u0e1a\u0e08.\u0e2a\u0e38\u0e20\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006911\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006911 \u0e1a\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e07\u0e32\u0e19\u0e1b\u0e39\u0e19 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006920\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e132026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006920 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e132026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e39\u0e49\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e35\u0e27\u0e35 \u5efa\u8a2d 261\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006938\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e-\u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006938 \u0e1a\u0e08.\u0e44\u0e2e-\u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u91d1\u878d\u30fb\u4fdd\u967a 140\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003718\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a8 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003718 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a8 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 998\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000849\",\"name_th\":\"\u0e2b\u0e08.\u0e13\u0e20\u0e31\u0e17\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e072026\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000849 \u0e2b\u0e08.\u0e13\u0e20\u0e31\u0e17\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e072026 2569-07-17 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e02\u0e38\u0e14 \u0e25\u0e2d\u0e01 \u0e16\u0e21\u0e14\u0e34\u0e19 \u5efa\u8a2d 53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0453569001063\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e34\u0e19\u0e1a\u0e38\u0e29 \u0e1a\u0e34\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001063 \u0e2b\u0e08.\u0e0a\u0e34\u0e19\u0e1a\u0e38\u0e29 \u0e1a\u0e34\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-17 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001511\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d.\u0e40\u0e2d\u0e47\u0e2126 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001511 \u0e1a\u0e08.\u0e44\u0e2d.\u0e40\u0e2d\u0e47\u0e2126 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 288  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0463569000741\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e31\u0e0a\u0e23\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000741 \u0e2b\u0e08.\u0e27\u0e31\u0e0a\u0e23\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-17 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e31\u0e1a\u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01 \u0e02\u0e38\u0e14\u0e04\u0e25\u0e2d\u0e07 \u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e17\u0e35\u0e48 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 207\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0473569000962\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e2b\u0e32\u0e28\u0e23\u0e35\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000962 \u0e2b\u0e08.\u0e21\u0e2b\u0e32\u0e28\u0e23\u0e35 2569-07-17 1000000 46204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0483569000521\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e19\u0e17\u0e4c\u0e1e\u0e31\u0e12\u0e18\u0e32\u0e1e\u0e37\u0e0a\u0e1c\u0e25\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000521 \u0e2b\u0e08.\u0e27\u0e34\u0e19\u0e17\u0e4c\u0e1e\u0e31\u0e12\u0e18\u0e32\u0e1e\u0e37\u0e0a\u0e1c\u0e25 2569-07-17 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0495569000549\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e25 \u0e17\u0e35 \u0e0a\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000549 \u0e1a\u0e08.\u0e27\u0e35\u0e25 \u0e17\u0e35 \u0e0a\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47222 \u0e1b\u0e23\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005017\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e21\u0e2d\u0e44\u0e0b\u0e04\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45405\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45405\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005017 \u0e2b\u0e08.\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e21\u0e2d\u0e44\u0e0b\u0e04\u0e4c 2569-07-17 1000000 45405 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 193\/77  \u0e16\u0e19\u0e19\u0e0a\u0e49\u0e32\u0e07\u0e40\u0e1c\u0e37\u0e2d\u0e01 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016151\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e04\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016151 \u0e1a\u0e08.\u0e44\u0e04\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 96302 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1e\u0e31\u0e01\u0e1e\u0e34\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e25\u0e30 \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 316  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016185\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016185 \u0e1a\u0e08.\u0e08\u0e35\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 8  \u0e0b\u0e2d\u0e22 3 (\u0e16\u0e19\u0e19\u0e2a\u0e27\u0e19\u0e14\u0e2d\u0e01) \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e19\u0e14\u0e2d\u0e01 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016193\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e42\u0e0a\u0e04 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016193 \u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e42\u0e0a\u0e04 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001439\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001439 \u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 298  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e21\u0e48\u0e2a\u0e32\u0e23\u0e1b\u0e48\u0e32\u0e41\u0e14\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0553569000431\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0553569000431 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35 2569-07-17 1000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 , \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32,\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 , \u0e23\u0e30\u0e1a\u0e1a \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0a\u0e25 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 \u5efa\u8a2d 174  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004632\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e44\u0e14\u0e2d\u0e32\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004632 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e44\u0e14\u0e2d\u0e32\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e33 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 258  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569002094\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33141\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33141\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002094 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 33141 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e40\u0e2b\u0e15\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23-\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u88fd\u9020 87\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002108\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e20\u0e39\u0e21\u0e34 \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002108 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e20\u0e39\u0e21\u0e34 \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e4d\u0e32\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 32\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0625569000792\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000792 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 113\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0655569002329\",\"name_th\":\"\u0e1a\u0e08. \u0e0b\u0e35\u0e19\u0e34\u0e18 \u0e1e\u0e31\u0e25\u0e2a\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002329 \u0e1a\u0e08. \u0e0b\u0e35\u0e19\u0e34\u0e18 \u0e1e\u0e31\u0e25\u0e2a\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1b\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 88\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0675569001527\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e25\u0e48\u0e32 \u0e25\u0e31\u0e01\u0e0a\u0e39\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001527 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e25\u0e48\u0e32 \u0e25\u0e31\u0e01\u0e0a\u0e39\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e21\u0e32\u0e42\u0e14\u0e22\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003243\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e19\u0e0b\u0e4c 168 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003243 \u0e1a\u0e08.\u0e40\u0e1a\u0e19\u0e0b\u0e4c 168 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04 \u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07 \u0e40\u0e04\u0e32\u0e30 \u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003251\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e04\u0e34\u0e14 \u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29102\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29102\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003251 \u0e1a\u0e08.\u0e18\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e04\u0e34\u0e14 \u0e14\u0e35\u0e44\u0e0b\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 29102 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 99\/139  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e04\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e42\u0e2e\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002697\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e44\u0e1e\u0e23\u0e0b\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002697 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e44\u0e1e\u0e23\u0e0b\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e41\u0e1c\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/2  \u0e16\u0e19\u0e19\u0e04\u0e39\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002719\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e23\u0e34\u0e0a \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002719 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e23\u0e34\u0e0a \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 97\/1  \u0e16\u0e19\u0e19\u0e41\u0e2a\u0e07\u0e0a\u0e39\u0e42\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001079\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e32\u0e04\u0e23\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001079 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e32\u0e04\u0e23 2569-07-17 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007532\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\u0e2e\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007532 \u0e1a\u0e08.\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\u0e2e\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1e\u0e37\u0e0a \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e38\u0e4b\u0e22 \u0e14\u0e34\u0e19\u0e1b\u0e25\u0e39\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110\/183  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e25\u0e04 \u0e0b\u0e35\u0e23\u0e35\u0e19 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007541\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e04\u0e32\u0e19\u0e32\u0e42\u0e2d\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007541 \u0e1a\u0e08.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e04\u0e32\u0e19\u0e32\u0e42\u0e2d\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 22220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e48\u0e2d\u0e19\u0e15\u0e31\u0e27 (flexible packaging) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17     \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e16\u0e38\u0e07\u0e23\u0e35\u0e17\u0e2d\u0e23\u0e4c\u0e15 (retort pouch) \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27     \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u88fd\u9020 49  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007575\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e17\u0e2d\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007575 \u0e1a\u0e08.\u0e1b\u0e25\u0e32\u0e17\u0e39\u0e17\u0e2d\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0803569001035\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e31\u0e27\u0e1a\u0e2d\u0e19\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001035 \u0e2b\u0e08.\u0e2b\u0e31\u0e27\u0e1a\u0e2d\u0e19 2569-07-17 1000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e0d\u0e49\u0e32 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e01\u0e34\u0e48\u0e07\u0e44\u0e21\u0e49 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e23\u0e07\u0e1e\u0e38\u0e48\u0e21 \u0e41\u0e1c\u0e49\u0e27\u0e16\u0e32\u0e07\u0e27\u0e31\u0e0a\u0e1e\u0e37\u0e0a \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e01\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 306\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0815569002131\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e34\u0e01\u0e1f\u0e49\u0e32\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002131 \u0e1a\u0e08.\u0e40\u0e1a\u0e34\u0e01\u0e1f\u0e49\u0e32\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 393  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0815569002149\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e42\u0e19\u0e40\u0e17\u0e25\u0e2d\u0e48\u0e32\u0e27\u0e19\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002149 \u0e1a\u0e08.\u0e42\u0e21\u0e42\u0e19\u0e40\u0e17\u0e25\u0e2d\u0e48\u0e32\u0e27\u0e19\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 1189  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0825569001177\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e17\u0e23\u0e32\u0e22\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46631\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46631\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001177 \u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e17\u0e23\u0e32\u0e22\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46631 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e38\u0e14 \u0e15\u0e31\u0e01 \u0e25\u0e2d\u0e01  \u0e14\u0e39\u0e14\u0e17\u0e23\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 97\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569013248\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e31\u0e15\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013248 \u0e1a\u0e08.\u0e17\u0e31\u0e15\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/2  \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e07\u0e28\u0e4c \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013256\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e0b\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013256 \u0e1a\u0e08.\u0e1a\u0e34\u0e0b\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07   \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/251  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013264\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013264 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e17\u0e23\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 18\/115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0843569001388\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e48\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001388 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e48\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-17 1000000 25119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e07\u0e32\u0e19\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 18\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0843569001396\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e39\u0e19\u0e1b\u0e31\u0e49\u0e19 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001396 \u0e2b\u0e08.\u0e1b\u0e39\u0e19\u0e1b\u0e31\u0e49\u0e19 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2569-07-17 1000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c\u0e1c\u0e2a\u0e21\u0e40\u0e2a\u0e23\u0e47\u0e08(\u0e1b\u0e39\u0e19\u0e21\u0e34\u0e01\u0e0b\u0e4c)\u0e41\u0e1c\u0e48\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e34\u0e10\u0e1a\u0e25\u0e47\u0e2d\u0e01 \u0e2d\u0e34\u0e10\u0e21\u0e27\u0e25 \u0e40\u0e1a\u0e32 \u0e2d\u0e34\u0e10\u0e21\u0e2d\u0e0d \u0e1a\u0e48\u0e2d\u0e1b\u0e39\u0e19 \u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21 \u0e40\u0e2a\u0e32\u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e04\u0e32\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e02\u0e19\u0e32\u0e14 \u88fd\u9020 77\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010541\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e1f\u0e41\u0e21\u0e01\u0e0b\u0e4c \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010541 \u0e1a\u0e08.\u0e40\u0e23\u0e1f\u0e41\u0e21\u0e01\u0e0b\u0e4c \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 43\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005864\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e17\u0e31\u0e48\u0e21 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005864 \u0e1a\u0e08.\u0e2d\u0e2d\u0e17\u0e31\u0e48\u0e21 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e07\u0e34\u0e19\u0e01\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19\u0e19\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19  \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23  \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19  \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e1f\u0e2d\u0e07\u0e0b\u0e34\u0e40\u0e2d\u0e23\u0e4c \u91d1\u878d\u30fb\u4fdd\u967a 3  \u0e0b\u0e2d\u0e22 20\/1 \u0e04\u0e25\u0e2d\u0e07\u0e40\u0e15\u0e22 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001061\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e49 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"53200\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"53200\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001061 \u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e49 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 53200 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 30\/11  \u0e16\u0e19\u0e19\u0e42\u0e23\u0e07\u0e1e\u0e31\u0e01 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0933569000321\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e40\u0e04\u0e23\u0e19\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0933569000321 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e40\u0e04\u0e23\u0e19 2569-07-17 1000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e02\u0e31\u0e1a (\u0e1c\u0e39\u0e49\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19) \u5efa\u8a2d 82\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0935569000846\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e35\u0e1f \u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000846 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e35\u0e1f \u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e21\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 229  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0965569000536\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e17\u0e23\u0e14 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0965569000536 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e17\u0e23\u0e14 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 1000000 46204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569007595\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007595 \u0e2b\u0e08.\u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 2569-07-16 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 111  \u0e0b\u0e2d\u0e22 \u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 4 \u0e16\u0e19\u0e19\u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007617\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e22\u0e04\u0e35 \u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47899\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47899\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007617 \u0e2b\u0e08.\u0e42\u0e22\u0e04\u0e35 \u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e14 2569-07-16 1000000 47899 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 19 \u0e41\u0e22\u0e01 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134181\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e04\u0e39\u0e2d\u0e04\u0e27\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e31\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134181 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e04\u0e39\u0e2d\u0e04\u0e27\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e31\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e04\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30 \u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 78\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21106 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21106 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134203\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e27\u0e2d\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47523\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47523\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134203 \u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e27\u0e2d\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47523 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e17\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e02\u0e49\u0e2d\u0e15\u0e48\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e14\u0e34\u0e19\u0e17\u0e48\u0e2d\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139  \u0e16\u0e19\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134211\",\"name_th\":\"\u0e1a\u0e08.136 \u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134211 \u0e1a\u0e08.136 \u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 398  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 67 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134220\",\"name_th\":\"\u0e1a\u0e08. \u0e2a\u0e49\u0e21\u0e40\u0e08\u0e4b\u0e07 \u0e21\u0e32\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134220 \u0e1a\u0e08. \u0e2a\u0e49\u0e21\u0e40\u0e08\u0e4b\u0e07 \u0e21\u0e32\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 592\/212  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134238\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e01\u0e0b\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134238 \u0e1a\u0e08.\u0e41\u0e21\u0e01\u0e0b\u0e35\u0e48\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1424\/231  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 16 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134246\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e21\u0e14\u0e31\u0e2a \u0e17\u0e31\u0e0a \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134246 \u0e1a\u0e08.\u0e44\u0e21\u0e14\u0e31\u0e2a \u0e17\u0e31\u0e0a \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07 (vr\/ar) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 189\/28  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e23\u0e34\u0e22\u0e32 \u0e42\u0e2e\u0e21\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 1\/5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134319\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e27\u0e32\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134319 \u0e1a\u0e08.\u0e25\u0e32\u0e27\u0e32\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e0a\u0e38\u0e14\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32 \u0e0a\u0e38\u0e14\u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19  \u0e0a\u0e38\u0e14\u0e40\u0e14\u0e47\u0e01 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/8  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134327\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e14\u0e35.\u0e2d\u0e35. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134327 \u0e1a\u0e08.\u0e40\u0e04.\u0e14\u0e35.\u0e2d\u0e35. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 1083\/84  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e34\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e1b\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e35\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e0b\u0e35 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134378\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e35\u0e2d\u0e2d\u0e19 \u0e1a\u0e31\u0e19\u0e22\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93210\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93210\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134378 \u0e1a\u0e08.\u0e19\u0e35\u0e2d\u0e2d\u0e19 \u0e1a\u0e31\u0e19\u0e22\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 93210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e15\u0e49\u0e15\u0e2d\u0e1a (interactive trivia) \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e42\u0e0a\u0e27\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e34\u0e28\u0e19\u0e32 (escape rooms) \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 (team-building) \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 (location-based entertainment) \u82b8\u8853\u30fb\u5a2f\u697d 79\/123  \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134394\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2d\u0e04\u0e04\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e32\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134394 \u0e1a\u0e08.\u0e21\u0e2d\u0e04\u0e04\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e32\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e2b\u0e49\u0e07 \u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 4\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134408\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e27\u0e32\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134408 \u0e1a\u0e08.\u0e40\u0e08\u0e27\u0e32\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e49\u0e32\u0e21\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134424\",\"name_th\":\"\u0e1a\u0e08.946 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134424 \u0e1a\u0e08.946 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e14\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e16 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e14\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48  \u0e16\u0e19\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134432\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e4a\u0e01 \u0e40\u0e08\u0e19 \u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134432 \u0e1a\u0e08.\u0e1a\u0e31\u0e4a\u0e01 \u0e40\u0e08\u0e19 \u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 275  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 80\/3 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134441\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e42\u0e1b\u0e23\u0e14\u0e1b\u0e23\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134441 \u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e42\u0e1b\u0e23\u0e14\u0e1b\u0e23\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 322\/14  \u0e16\u0e19\u0e19\u0e2d\u0e42\u0e28\u0e01-\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134459\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2d\u0e2d\u0e19 \u0e19\u0e20\u0e27\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134459 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2d\u0e2d\u0e19 \u0e19\u0e20\u0e27\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e28\u0e35\u0e23\u0e29\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34 \u0e41\u0e0a\u0e21\u0e1e\u0e39 \u0e04\u0e23\u0e35\u0e21\u0e19\u0e27\u0e14\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e40\u0e08\u0e25\u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e08\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e17\u0e23\u0e07\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e35\u0e1c\u0e21 \u0e19\u0e4d\u0e49\u0e32\u0e22\u0e32\u0e14\u0e31\u0e14\u0e1c\u0e21 \u0e19\u0e4d\u0e49\u0e32\u0e22\u0e32\u0e42\u0e01\u0e23\u0e01\u0e1c\u0e21 \u0e41\u0e2e\u0e23\u0e4c\u0e42\u0e17\u0e19\u0e34\u0e04 \u0e41\u0e2e\u0e23\u0e4c\u0e40\u0e0b\u0e23\u0e31\u0e48\u0e21 \u0e41\u0e2e\u0e23\u0e4c\u0e21\u0e34\u0e2a\u0e15\u0e4c \u0e41\u0e2e\u0e23\u0e4c\u0e21\u0e32\u0e2a\u0e01\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 58,60,62,64,66  \u0e0b\u0e2d\u0e22 \u0e2a\u0e23\u0e13\u0e04\u0e21\u0e19\u0e4c 10 \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e13\u0e04\u0e21\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134467\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52299\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52299\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134467 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 52299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (electric vehicle charging station) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 15\/21  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134483\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e44\u0e17-\u0e27\u0e31\u0e19\u0e0a\u0e37\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134483 \u0e1a\u0e08.\u0e2a\u0e21\u0e44\u0e17-\u0e27\u0e31\u0e19\u0e0a\u0e37\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 433  \u0e0b\u0e2d\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e16\u0e19\u0e19\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a 17 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134491\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e2a\u0e44\u0e1b\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134491 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e44\u0e2d \u0e2d\u0e34\u0e19\u0e2a\u0e44\u0e1b\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 293\/47  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 6\/1 \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134513\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e27\u0e23\u0e38\u0e13 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86902\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86902\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134513 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e27\u0e23\u0e38\u0e13 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 86902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35 \u0e1e\u0e34\u0e25\u0e32\u0e17\u0e34\u0e2a \u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22(\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u533b\u7642\u30fb\u798f\u7949 86  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e25\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 86\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134521\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134521 \u0e1a\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e07\u0e42\u0e09\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e1a\u0e39\u0e48 \u0e22\u0e32\u0e2a\u0e35\u0e1f\u0e31\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/26  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134548\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e22\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46432\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46432\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134548 \u0e1a\u0e08.\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e22\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46432 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e37\u0e48\u0e2d\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 748 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134556\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e14\u0e35 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134556 \u0e1a\u0e08.\u0e27\u0e14\u0e35 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d (7) \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/797  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e23\u0e38\u0e13\u0e17\u0e2d\u0e07 \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d 8\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134564\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e38\u0e49\u0e07\u0e17\u0e2d\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134564 \u0e1a\u0e08.\u0e01\u0e38\u0e49\u0e07\u0e17\u0e2d\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e2d\u0e07\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e38\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e49\u0e07 \u0e22\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u5bbf\u6cca\u30fb\u98f2\u98df 579\/1  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134572\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e17\u0e35\u0e21\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134572 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e17\u0e35\u0e21\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e01\u0e41\u0e25\u0e47\u0e04\u0e0b\u0e35\u0e48\u0e40\u0e1e\u0e25\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4\/2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134611\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e32 \u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134611 \u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e32 \u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 109  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134629\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e2a\u0e48\u0e43\u0e08 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134629 \u0e1a\u0e08.\u0e43\u0e2a\u0e48\u0e43\u0e08 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2b\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2b\u0e34\u0e19 \u0e1e\u0e25\u0e2d\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e07\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07 \u0e01\u0e33\u0e44\u0e25\u0e21\u0e07\u0e04\u0e25  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/144  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 15 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134637\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e40\u0e0b\u0e44\u0e04 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58201\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58201\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134637 \u0e1a\u0e08.\u0e2d\u0e34\u0e40\u0e0b\u0e44\u0e04 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 58201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e40\u0e01\u0e21 \u0e40\u0e01\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e01\u0e21\u0e1a\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 48  \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e18\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134645\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e04\u0e31\u0e21 \u0e21\u0e34\u0e2a\u0e40\u0e17\u0e04 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134645 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e04\u0e31\u0e21 \u0e21\u0e34\u0e2a\u0e40\u0e17\u0e04 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e2e\u0e2a\u0e40\u0e17\u0e25 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 748  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 30\/1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134653\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e40\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134653 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e40\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e21\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1580  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 63 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134661\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e04\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134661 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e04\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1\/11  \u0e0b\u0e2d\u0e22 \u0e41\u0e22\u0e01\u0e0b\u0e2d\u0e22\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134688\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e27\u0e35 \u0e40\u0e23\u0e19\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134688 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e27\u0e35 \u0e40\u0e23\u0e19\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e25\u0e35\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e02\u0e19\u0e32\u0e14 \u0e23\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 (big bike) \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e1b\u0e35 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 300\/37  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134734\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134734 \u0e1a\u0e08.\u0e1e\u0e35\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 157  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134742\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134742 \u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 56\/3  \u0e16\u0e19\u0e19\u0e23\u0e30\u0e19\u0e2d\u0e07 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134785\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e32\u0e22  \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134785 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e32\u0e22  \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e32\u0e01\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e32\u0e21\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u82b8\u8853\u30fb\u5a2f\u697d 112\/3  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134815\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e0b\u0e41\u0e25\u0e47\u0e1a \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134815 \u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e0b\u0e41\u0e25\u0e47\u0e1a \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e23\u0e16\u0e21\u0e37\u0e2d2 \u0e02\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 725\/59  \u0e16\u0e19\u0e19\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134858\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1f\u0e42\u0e15 \u0e40\u0e21\u0e14\u0e34\u0e40\u0e04\u0e21 \u0e23\u0e35\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134858 \u0e1a\u0e08.\u0e44\u0e1f\u0e42\u0e15 \u0e40\u0e21\u0e14\u0e34\u0e40\u0e04\u0e21 \u0e23\u0e35\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e2a\u0e01\u0e31\u0e14 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e31\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2b\u0e32\u0e01\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e14\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 255\/1  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134866\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134866 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e2d\u0e19\u0e38\u0e0a 70\/1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 77 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134904\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e25 \u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04\u0e40\u0e04\u0e34\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134904 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e25 \u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04\u0e40\u0e04\u0e34\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 85\/1  \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134912\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e23\u0e31\u0e25 \u0e42\u0e19\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134912 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e23\u0e31\u0e25 \u0e42\u0e19\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83\/196  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 14 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134921\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e19\u0e34\u0e19\u0e35 \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21 \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134921 \u0e1a\u0e08.\u0e1e\u0e32\u0e19\u0e34\u0e19\u0e35 \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21 \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 239\/84  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002496\",\"name_th\":\"\u0e2b\u0e08. \u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002496 \u0e2b\u0e08. \u0e40\u0e01\u0e29\u0e15\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c 2569-07-16 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 8\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002500\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e23\u0e48\u0e04\u0e38\u0e13\u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002500 \u0e2b\u0e08.\u0e44\u0e23\u0e48\u0e04\u0e38\u0e13\u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-16 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 8\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002518\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e23\u0e48\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002518 \u0e2b\u0e08.\u0e44\u0e23\u0e48\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-16 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002534\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e01\u0e38\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e0b\u0e2d\u0e22\u0e25\u0e4c \u0e42\u0e1a\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e2a\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002534 \u0e2b\u0e08.\u0e2a\u0e01\u0e38\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e0b\u0e2d\u0e22\u0e25\u0e4c \u0e42\u0e1a\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e2a 2569-07-16 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e18\u0e23\u0e13\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e0a\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e13\u0e35 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e08\u0e32\u0e30\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e0a\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e40\u0e08\u0e32\u0e30\u0e1a\u0e48\u0e2d\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e07\u0e32\u0e19\u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e07\u0e32\u0e19\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01 \u0e07\u0e32\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 58\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023487\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e2e\u0e2d\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e49\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023487 \u0e1a\u0e08.\u0e19\u0e34\u0e2e\u0e2d\u0e19 \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e49\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 (delivery) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 107\/143  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e25\u0e0a\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e01\u0e21.10 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023517\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e23\u0e34\u0e28\u0e34\u0e27\u0e32 \u0e01\u0e23\u0e35\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23939\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23939\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023517 \u0e1a\u0e08.\u0e22\u0e39\u0e23\u0e34\u0e28\u0e34\u0e27\u0e32 \u0e01\u0e23\u0e35\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 23939 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e47\u0e14\u0e14\u0e34\u0e19\u0e40\u0e1c\u0e32 \u0e43\u0e1a\u0e42\u0e2d\u0e0a\u0e32 \u0e1b\u0e38\u0e4b\u0e22 \u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 799\/219  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e32\u0e0b\u0e48\u0e32\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e2890 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e2890 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023541\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e19\u0e35 \u0e17\u0e23\u0e31\u0e04\u0e2a\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"30990\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"30990\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023541 \u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e19\u0e35 \u0e17\u0e23\u0e31\u0e04\u0e2a\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 30990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e04\u0e25\u0e38\u0e21\u0e1c\u0e49\u0e32\u0e43\u0e1a \u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 101\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023550\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e25\u0e31\u0e01\u0e29\u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46499\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46499\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023550 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e25\u0e31\u0e01\u0e29\u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e15\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e09\u0e25\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (label) \u0e1a\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14 \u0e04\u0e34\u0e27\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14 (qr code) \u0e1b\u0e49\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e1b\u0e49\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1b\u0e49\u0e32\u0e22\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e09\u0e25\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 (thermal label) \u0e23\u0e34\u0e1a\u0e1a\u0e2d\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1a\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e09\u0e25\u0e32\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 829\/152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023576\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e01\u0e35\u0e49 \u0e2b\u0e21\u0e39 \u0e2b\u0e21\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023576 \u0e1a\u0e08.\u0e2a\u0e38\u0e01\u0e35\u0e49 \u0e2b\u0e21\u0e39 \u0e2b\u0e21\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e01\u0e35\u0e49\u0e22\u0e32\u0e01\u0e35\u0e49 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e49\u0e21 \u0e15\u0e38\u0e4b\u0e19 \u0e17\u0e2d\u0e14 \u0e1c\u0e31\u0e14 \u0e1b\u0e34\u0e49\u0e07 \u0e22\u0e48\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e02\u0e36\u0e49\u0e19-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e4d\u0e49\u0e32\u0e08\u0e34\u0e49\u0e21 \u0e0b\u0e2d\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e49\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e2f \u5bbf\u6cca\u30fb\u98f2\u98df 159\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023592\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e23\u0e35\u0e1a\u0e2d\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023592 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e23\u0e35\u0e1a\u0e2d\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023606\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e14\u0e35\u0e40\u0e2e\u0e07\u0e14\u0e35789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023606 \u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e14\u0e35\u0e40\u0e2e\u0e07\u0e14\u0e35789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002186\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e0a\u0e0a\u0e4c\u0e23\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c88\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002186 \u0e2b\u0e08.\u0e23\u0e31\u0e0a\u0e0a\u0e4c\u0e23\u0e27\u0e34\u0e19\u0e17\u0e23\u0e4c88 2569-07-16 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u5efa\u8a2d 7\/551  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0123569002194\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e41\u0e1e\u0e23\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002194 \u0e2b\u0e08.\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e41\u0e1e\u0e23 2569-07-16 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 195  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c 17 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0123569002208\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e38\u0e01\u0e17\u0e32\u0e07\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002208 \u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e38\u0e01\u0e17\u0e32\u0e07 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e15\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f\u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 99\/200  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0123569002216\",\"name_th\":\"\u0e2b\u0e08.88 \u0e2d\u0e21\u0e39\u0e40\u0e25\u0e17\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002216 \u0e2b\u0e08.88 \u0e2d\u0e21\u0e39\u0e40\u0e25\u0e17 2569-07-16 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e35\u0e48\u0e21\u0e23\u0e04\u0e48\u0e32\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93\/651  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e28\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026702\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e25\u0e34\u0e1f\u0e40\u0e1a\u0e0b\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026702 \u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e25\u0e34\u0e1f\u0e40\u0e1a\u0e0b\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 8\/18  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026711\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e23\u0e19 \u0e41\u0e2d\u0e17\u0e40\u0e17\u0e25\u0e34\u0e40\u0e22\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026711 \u0e1a\u0e08.\u0e27\u0e32\u0e22\u0e40\u0e23\u0e19 \u0e41\u0e2d\u0e17\u0e40\u0e17\u0e25\u0e34\u0e40\u0e22\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 97\/32  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e32\u0e23\u0e2d\u0e19\u0e40\u0e19\u0e35\u0e22\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e28\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07 3 \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e19\u0e49\u0e33\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026729\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e27\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026729 \u0e1a\u0e08.\u0e1e\u0e35\u0e27\u0e35\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e25\u0e2b\u0e30\u0e41\u0e25\u0e30\u0e2d\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/6   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 dd 2\/1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026745\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e10\u0e32\u0e1b\u0e39\u0e17\u0e30\u0e40\u0e25\u0e17\u0e2d\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026745 \u0e1a\u0e08.\u0e19\u0e34\u0e10\u0e32\u0e1b\u0e39\u0e17\u0e30\u0e40\u0e25\u0e17\u0e2d\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 523\/1  \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026770\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e35\u0e40\u0e08 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026770 \u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e35\u0e40\u0e08 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/482  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026796\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e0a\u0e49\u0e2d\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026796 \u0e1a\u0e08.\u0e08\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e0a\u0e49\u0e2d\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17(\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u60c5\u5831\u901a\u4fe1\u30fbit 15  \u0e0b\u0e2d\u0e22 \u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e3515 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026818\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e10\u0e21\u0e32\u0e20\u0e23\u0e13\u0e4c 36 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026818 \u0e1a\u0e08.\u0e1b\u0e10\u0e21\u0e32\u0e20\u0e23\u0e13\u0e4c 36 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 22\/88   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 110 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026834\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026834 \u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 6  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026869\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e08\u0e35\u0e40\u0e2d \u0e2a\u0e01\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026869 \u0e1a\u0e08.\u0e0b\u0e35\u0e08\u0e35\u0e40\u0e2d \u0e2a\u0e01\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 85410 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e25\u0e30\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46            \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 fitting \u0e44\u0e21\u0e49\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u6559\u80b2 88\/888  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026877\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e47\u0e17 \u0e2d\u0e31\u0e2a \u0e14\u0e39 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026877 \u0e1a\u0e08.\u0e40\u0e25\u0e47\u0e17 \u0e2d\u0e31\u0e2a \u0e14\u0e39 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 70209 \u0e40\u0e1b\u0e34\u0e14\u0e02\u0e32\u0e22\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e19\u0e31\u0e49\u0e19 \u0e46 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e17\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e41\u0e0a\u0e17\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e40\u0e07\u0e34\u0e19 (\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 45\/96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026893\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22 \u0e14\u0e31\u0e07 \u0e1b\u0e31\u0e07 \u0e14\u0e35 \u0e1a\u0e32\u0e22 \u0e08\u0e4a\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026893 \u0e1a\u0e08.\u0e23\u0e27\u0e22 \u0e14\u0e31\u0e07 \u0e1b\u0e31\u0e07 \u0e14\u0e35 \u0e1a\u0e32\u0e22 \u0e08\u0e4a\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e1a\u0e34\u0e49\u0e27\u0e2d\u0e34\u0e19 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 59\/122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026915\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026915 \u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e39\u0e01\u0e02\u0e32\u0e14\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e41\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u9271\u696d\u30fb\u63a1\u77f3 162\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026923\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e19\u0e33\u0e42\u0e0a\u0e04 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026923 \u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e19\u0e33\u0e42\u0e0a\u0e04 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e39\u0e01\u0e02\u0e32\u0e14\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e41\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u9271\u696d\u30fb\u63a1\u77f3 162\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026931\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e28\u0e23\u0e35\u0e21\u0e07\u0e04\u0e25 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026931 \u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e28\u0e23\u0e35\u0e21\u0e07\u0e04\u0e25 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e39\u0e01\u0e02\u0e32\u0e14\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e41\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u9271\u696d\u30fb\u63a1\u77f3 162\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026940\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e17\u0e35\u0e0b\u0e35\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026940 \u0e1a\u0e08.\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e17\u0e35\u0e0b\u0e35\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21 \u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e1f\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026958\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026958 \u0e1a\u0e08.\u0e17\u0e33\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 108\/166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002496\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002496 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e41\u0e1f\u0e1a\u0e23\u0e34\u0e04 2569-07-16 1000000 46411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e1a \u0e1c\u0e49\u0e32\u0e21\u0e49\u0e27\u0e19 \u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/225  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1f\u0e49\u0e32\u0e1b\u0e34\u0e22\u0e23\u0e21\u0e22\u0e4c \u0e40\u0e17\u0e19\u0e42\u0e14\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021808\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e39 \u0e40\u0e21\u0e17 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021808 \u0e1a\u0e08.\u0e17\u0e23\u0e39 \u0e40\u0e21\u0e17 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 98\/168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021816\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e08\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021816 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e08\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 43\/73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021832\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e0a\u0e1e\u0e35 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021832 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e0a\u0e1e\u0e35 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u4e0d\u52d5\u7523 77\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021841\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e2a\u0e1e\u0e35 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021841 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e2a\u0e1e\u0e35 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u4e0d\u52d5\u7523 77\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021859\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35 \u0e40\u0e08\u0e35\u0e4a\u0e22\u0e1a \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58133\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58133\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021859 \u0e1a\u0e08.\u0e2d\u0e35 \u0e40\u0e08\u0e35\u0e4a\u0e22\u0e1a \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 58133 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e42\u0e0b\u0e40\u0e0b\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e1e\u0e23\u0e48\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e1a \u60c5\u5831\u901a\u4fe1\u30fbit 176  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 39 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021875\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021875 \u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 141 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e2d\u0e25\u0e25\u0e4c   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 141\/27,28 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021891\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e0b\u0e47\u0e17 \u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52231\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52231\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021891 \u0e1a\u0e08. \u0e40\u0e0b\u0e47\u0e17 \u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 52231 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19  \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 80\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021905\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e31\u0e19 \u0e40\u0e1f\u0e23\u0e0a \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021905 \u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e31\u0e19 \u0e40\u0e1f\u0e23\u0e0a \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07-\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/206  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021913\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e2d\u0e1b \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021913 \u0e1a\u0e08.\u0e14\u0e23\u0e2d\u0e1b \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 77101 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e1a\u0e1a\u0e25\u0e35\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30 \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 299\/45  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e19\u0e40\u0e27\u0e25 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021930\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021930 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021948\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e49\u0e2d\u0e21\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e04\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021948 \u0e1a\u0e08.\u0e2d\u0e49\u0e2d\u0e21\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e04\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 10751 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u88fd\u9020 89\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004695\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e01\u0e25\u0e49\u0e22\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004695 \u0e1a\u0e08.\u0e43\u0e01\u0e25\u0e49\u0e22\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 21001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 19\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004709\",\"name_th\":\"\u0e1a\u0e08.3\u0e1e\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004709 \u0e1a\u0e08.3\u0e1e\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e02\u0e2d\u0e07\u0e0a\u0e33 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001645\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e14\u0e23\u0e32\u0e22 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10419\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10419\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001645 \u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e14\u0e23\u0e32\u0e22 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 10419 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 78\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002587\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e17\u0e2d\u0e07\u0e1f\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002587 \u0e1a\u0e08.\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e17\u0e2d\u0e07\u0e1f\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1c\u0e2a\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2b\u0e31\u0e27\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e27\u0e01\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e40\u0e01\u0e25\u0e37\u0e2d\u0e41\u0e23\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002595\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e17\u0e35\u0e0b\u0e35 \u0e42\u0e1e\u0e23\u0e27\u0e32\u0e22\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002595 \u0e1a\u0e08.\u0e1a\u0e35\u0e17\u0e35\u0e0b\u0e35 \u0e42\u0e1e\u0e23\u0e27\u0e32\u0e22\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e44\u0e2b\u0e21\u0e49 \u0e23\u0e30\u0e1a\u0e1a\u0e25\u0e34\u0e1f\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e21\u0e25\u0e1e\u0e34\u0e29\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e21\u0e25\u0e1e\u0e34\u0e29\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e21\u0e25\u0e1e\u0e34\u0e29\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e21\u0e49\u0e2d\u0e15\u0e49\u0e21 \u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e16\u0e31\u0e07\u0e17\u0e19\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 29\/129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002609\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e0b\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002609 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e0b\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003114\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e08 \u0e40\u0e19\u0e34\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e41\u0e04\u0e23\u0e4c\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003114 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e08 \u0e40\u0e19\u0e34\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e41\u0e04\u0e23\u0e4c 2569-07-16 1000000 78300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e35\u0e21\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 99\/124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037487\",\"name_th\":\"\u0e1a\u0e08.24 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037487 \u0e1a\u0e08.24 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 49334 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 456\/238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037495\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0a\u0e25\u0e18\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037495 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0a\u0e25\u0e18\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46315 \u0e02\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e16\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037509\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e1f \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037509 \u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e1f \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037517\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e39\u0e1f\u0e17\u0e47\u0e2d\u0e1b \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037517 \u0e1a\u0e08.\u0e23\u0e39\u0e1f\u0e17\u0e47\u0e2d\u0e1b \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 113\/12  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2-3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 15 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0243569000701\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e18\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000701 \u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e18\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-16 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 89\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003876\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e31\u0e19 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003876 \u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e31\u0e19 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 16\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0265569000818\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35 \u0e04\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000818 \u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35 \u0e04\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u88fd\u9020 188  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0275569001121\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e2d\u0e07\u0e1c\u0e01\u0e32  \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001121 \u0e1a\u0e08.\u0e01\u0e2d\u0e07\u0e1c\u0e01\u0e32  \u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002761\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e34\u0e1b\u0e34\u0e40\u0e25\u0e34\u0e28 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002761 \u0e2b\u0e08.\u0e25\u0e34\u0e1b\u0e34\u0e40\u0e25\u0e34\u0e28 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-16 1000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e2d\u0e1a\u0e1c\u0e49\u0e32 \u0e23\u0e35\u0e14\u0e1c\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 323\/134  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 14 \u0e0b\u0e2d\u0e22 4 \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007331\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e39\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007331 \u0e1a\u0e08.\u0e19\u0e39\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c (solar cell) \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 999  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007340\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e32\u0e18\u0e23 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25921\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25921\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007340 \u0e1a\u0e08.\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e32\u0e18\u0e23 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 25921 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e02\u0e31\u0e14 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 1112\/148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007358\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e2b\u0e25\u0e48\u0e2d\u0e23\u0e31\u0e49\u0e27\u0e04\u0e32\u0e27\u0e1a\u0e2d\u0e22 \u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007358 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e2b\u0e25\u0e48\u0e2d\u0e23\u0e31\u0e49\u0e27\u0e04\u0e32\u0e27\u0e1a\u0e2d\u0e22 \u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e31\u0e49\u0e27\u0e04\u0e32\u0e27\u0e1a\u0e2d\u0e22 \u0e23\u0e32\u0e07\u0e27\u0e35 \u0e17\u0e38\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007366\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e39\u0e49\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 99 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007366 \u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e39\u0e49\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 99 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007382\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04 \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007382 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04 \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007391\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e18\u0e35 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007391 \u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e18\u0e35 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21-\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e \u533b\u7642\u30fb\u798f\u7949 499\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001902\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20231\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20231\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001902 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e40\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 20231 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 (oem\/odm) \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e32\u0e23\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 216\/26-27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569001911\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e34\u0e49\u0e21\u0e07\u0e48\u0e32\u0e22\u0e1a\u0e32\u0e22\u0e2d\u0e35\u0e0b\u0e35\u0e48\u0e2a\u0e21\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001911 \u0e1a\u0e08.\u0e22\u0e34\u0e49\u0e21\u0e07\u0e48\u0e32\u0e22\u0e1a\u0e32\u0e22\u0e2d\u0e35\u0e0b\u0e35\u0e48\u0e2a\u0e21\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 350\/10-11  \u0e16\u0e19\u0e19\u0e08\u0e34\u0e23\u0e30 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0325569001244\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32 \u0e23\u0e35. \u0e1a\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001244 \u0e1a\u0e08.\u0e2d\u0e32 \u0e23\u0e35. \u0e1a\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0335569001147\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001147 \u0e1a\u0e08.\u0e17\u0e35.\u0e44\u0e0b\u0e19\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 (\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e35) \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 - \u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 - \u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569001927\",\"name_th\":\"\u0e2b\u0e08.\u0e2a.\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e14\u0e32 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001927 \u0e2b\u0e08.\u0e2a.\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e14\u0e32 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e17\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d \u0e17\u0e33\u0e16\u0e19\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u5efa\u8a2d 141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003239\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003239 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1a\u0e32\u0e23\u0e4c \u0e1c\u0e31\u0e1a \u0e04\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e38\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e02\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 29\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0353569000483\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e07\u0e04\u0e4c\u0e14\u0e32\u0e25\u0e32 2026\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000483 \u0e2b\u0e08.\u0e23\u0e07\u0e04\u0e4c\u0e14\u0e32\u0e25\u0e32 2026 2569-07-16 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 424  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0363569000912\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35.\u0e40\u0e04. \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2026\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000912 \u0e2b\u0e08.\u0e1e\u0e35.\u0e40\u0e04. \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2026 2569-07-16 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0363569000921\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e27\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000921 \u0e2b\u0e08.\u0e14\u0e27\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 378  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0375569000396\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e22\u0e32 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10743\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10743\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0375569000396 \u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e22\u0e32 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 10743 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e49\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e08\u0e31\u0e4a\u0e1a \u0e40\u0e2a\u0e49\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e27\u0e38\u0e49\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003210\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 589\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003210 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 589 2569-07-16 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e14\u0e22\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e1b\u0e01\u0e15\u0e34\u0e08\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 178\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001632\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e48\u0e2d\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47733\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47733\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001632 \u0e2b\u0e08.\u0e1e\u0e48\u0e2d\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-16 1000000 47733 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0435569001120\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e07\u0e27\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001120 \u0e1a\u0e08.\u0e41\u0e1a\u0e07\u0e27\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0455569001502\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e0b\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001502 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e0b\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e28\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0473569000954\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e14\u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000954 \u0e2b\u0e08.\u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e14\u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e27\u0e32\u0e19\u0e23-\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0b\u0e37\u0e2d\u0e21 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004975\",\"name_th\":\"\u0e2b\u0e08.3 \u0e27\u0e2d \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004975 \u0e2b\u0e08.3 \u0e27\u0e2d \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-16 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u904b\u8f38\u30fb\u7269\u6d41 290  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016029\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016029 \u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 222\/61  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e47\u0e21\u0e40\u0e1e\u0e2d\u0e40\u0e23\u0e48\u0e2d 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 4b \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016037\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86903\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86903\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016037 \u0e1a\u0e08.\u0e22\u0e39 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 86903 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e25\u0e37\u0e2d\u0e14 \u0e1b\u0e31\u0e2a\u0e2a\u0e32\u0e27\u0e30 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e08\u0e08\u0e32\u0e23\u0e30 \u533b\u7642\u30fb\u798f\u7949 450  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016045\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016045 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1c\u0e07\u0e21\u0e31\u0e08\u0e09\u0e30 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016053\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e32\u0e20\u0e39\u0e21\u0e34  \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016053 \u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e32\u0e20\u0e39\u0e21\u0e34  \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41002 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 188  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016070\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e0a\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016070 \u0e1a\u0e08.\u0e1f\u0e32\u0e0a\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e07\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 400\/1-2  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016088\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e42\u0e14\u0e49\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016088 \u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e42\u0e14\u0e49\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 415  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016100\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 1989 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016100 \u0e1a\u0e08.\u0e40\u0e08 \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 1989 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 190\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016134\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016134 \u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e02\u0e31\u0e1a \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 88\/328  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016142\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e40\u0e23\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016142 \u0e1a\u0e08.\u0e0b\u0e39\u0e40\u0e23\u0e40\u0e27\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence: ai) \u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data analytics) \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c (cloud computing) \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c (cybersecurity) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 402  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000732\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e38\u0e20\u0e1e\u0e07\u0e29\u0e4c 333\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000732 \u0e2b\u0e08.\u0e28\u0e38\u0e20\u0e1e\u0e07\u0e29\u0e4c 333 2569-07-16 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 333  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e25\u0e48\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0543569000287\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23 89 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0543569000287 \u0e2b\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23 89 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-16 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0575569004594\",\"name_th\":\"\u0e1a\u0e08.9 \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004594 \u0e1a\u0e08.9 \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 857\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569002060\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e40\u0e2d\u0e25\u0e34\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002060 \u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e40\u0e2d\u0e25\u0e34\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002086\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1a\u0e35\u0e42\u0e2e\u0e21\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002086 \u0e1a\u0e08.\u0e40\u0e08\u0e1a\u0e35\u0e42\u0e2e\u0e21\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 383  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0633569000731\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e31\u0e22\u0e22\u0e30\u0e17\u0e27\u0e35\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000731 \u0e2b\u0e08.\u0e0a\u0e31\u0e22\u0e22\u0e30\u0e17\u0e27\u0e35 2569-07-16 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22\u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0653569001126\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e01\u0e42\u0e01 \u0e21\u0e32\u0e23\u0e4c\u0e17\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001126 \u0e2b\u0e08.\u0e42\u0e01\u0e42\u0e01 \u0e21\u0e32\u0e23\u0e4c\u0e17 2569-07-16 1000000 47113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e21\u0e34\u0e19\u0e34\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002302\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e14\u0e39\u0e27\u0e4c 456 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002302 \u0e1a\u0e08.\u0e25\u0e2d\u0e07\u0e14\u0e39\u0e27\u0e4c 456 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 92\/1  \u0e16\u0e19\u0e19\u0e27\u0e31\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0715569002689\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e39\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002689 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e39\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e40\u0e0a\u0e48\u0e19 \u0e1f\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e38\u0e49\u0e21\u0e15\u0e32\u0e02\u0e48\u0e32\u0e22 \u0e1d\u0e2d\u0e22\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e1f\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e15\u0e34\u0e14\u0e44\u0e1a\u0e23\u0e4c\u0e17 \u0e41\u0e1b\u0e23\u0e07\u0e02\u0e31\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e08\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 114\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002131\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e40\u0e17\u0e1e\u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e25\u0e14\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002131 \u0e1a\u0e08.\u0e2a\u0e38\u0e40\u0e17\u0e1e\u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e25\u0e14\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 389  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002140\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e04 \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002140 \u0e1a\u0e08.\u0e0a\u0e34\u0e04 \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001052\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0b\u0e31\u0e19\u0e2b\u0e21\u0e39\u0e2a\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001052 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0b\u0e31\u0e19\u0e2b\u0e21\u0e39\u0e2a\u0e14 2569-07-16 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0733569001061\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32 \u0e44\u0e01\u0e48\u0e2a\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001061 \u0e2b\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32 \u0e44\u0e01\u0e48\u0e2a\u0e14 2569-07-16 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07  \u0e44\u0e01\u0e48\u0e2a\u0e14 \u0e2b\u0e21\u0e39\u0e2a\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007184\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10802\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10802\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007184 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 10802 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e04\u0e49\u0e19\u0e2a\u0e39\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e04\u0e49\u0e32\u0e19\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e23\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e42\u0e19 \u0e19\u0e34\u0e27\u0e04\u0e25\u0e35\u0e42\u0e2d\u0e44\u0e17\u0e14\u0e4c \u0e40\u0e1b\u0e1b\u0e44\u0e17\u0e14\u0e4c \u0e40\u0e2d\u0e19\u0e44\u0e0b\u0e21\u0e4c \u0e42\u0e1b\u0e23\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 \u0e1e\u0e23\u0e35\u0e44\u0e1a\u0e42\u0e2d\u0e15\u0e34\u0e01 \u0e01\u0e23\u0e14\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e2a\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a \u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u88fd\u9020 248  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007192\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e47\u0e17\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007192 \u0e1a\u0e08.\u0e40\u0e27\u0e47\u0e17\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007206\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007206 \u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 212\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007214\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e38\u0e07\u0e40\u0e07\u0e34\u0e19\u0e16\u0e38\u0e07\u0e17\u0e2d\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007214 \u0e1a\u0e08.\u0e16\u0e38\u0e07\u0e40\u0e07\u0e34\u0e19\u0e16\u0e38\u0e07\u0e17\u0e2d\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46639 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e01\u0e23\u0e27\u0e14 \u0e2a\u0e35\u0e17\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e0a\u0e31\u0e01\u0e40\u0e07\u0e32 \u0e27\u0e2d\u0e25\u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e01\u0e23\u0e30\u0e08\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e0a\u0e48\u0e19 \u0e04\u0e49\u0e2d\u0e19 \u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22 \u0e44\u0e02\u0e04\u0e27\u0e07 \u0e01\u0e38\u0e0d\u0e41\u0e08 \u0e1a\u0e32\u0e19\u0e1e\u0e31\u0e1a \u0e15\u0e30\u0e1b\u0e39 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07  \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e35\u0e49\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22\u0e1c\u0e2a\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e31\u0e14\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e39\u0e19\u0e0b\u0e34\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e1b\u0e39\u0e19\u0e1b\u0e25\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e36\u0e14\u0e15\u0e34\u0e14\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e41\u0e23\u0e48\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e44\u0e21\u0e49\u0e1d\u0e32\u0e40\u0e0c\u0e2d\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e40\u0e23\u0e35\u0e22\u0e1a \u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e01\u0e49\u0e2d\u0e19\u0e2d\u0e34\u0e10 \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e1a\u0e32\u0e19\u0e40\u0e01\u0e25\u0e47\u0e14 \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e2d\u0e1a \u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007443\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e1a\u0e38\u0e0d\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007443 \u0e1a\u0e08.\u0e1e\u0e23\u0e1a\u0e38\u0e0d\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007451\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e01 \u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007451 \u0e1a\u0e08.\u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e23\u0e31\u0e01 \u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007460\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e21\u0e34\u0e49\u0e19 \u0e04\u0e39\u0e01\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007460 \u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e21\u0e34\u0e49\u0e19 \u0e04\u0e39\u0e01\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 108\/204  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007478\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e17 \u0e1e\u0e25\u0e35\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007478 \u0e1a\u0e08.\u0e1a\u0e2d\u0e17 \u0e1e\u0e25\u0e35\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e21\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e15 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u6559\u80b2 139\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007486\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e18\u0e0d\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007486 \u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e18\u0e0d\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 28\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007494\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007494 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 157\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007508\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e28\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007508 \u0e1a\u0e08.\u0e1e\u0e28\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007524\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e40\u0e17\u0e47\u0e14 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e2d\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007524 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e40\u0e17\u0e47\u0e14 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e2d\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e27\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e1b\u0e25\u0e32\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 181\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0773569000412\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e21\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e0b\u0e35\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0773569000412 \u0e2b\u0e08.\u0e1a\u0e35\u0e21\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e0b\u0e35 2569-07-16 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e22\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 201\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0775569003031\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e21\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003031 \u0e1a\u0e08.\u0e23\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e21\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23 \u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e19\u0e32\u0e07\u0e41\u0e1a\u0e1a \u0e19\u0e32\u0e22\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e1c\u0e39\u0e49\u0e21\u0e35 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0803569001019\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e08\u0e34\u0e19\u0e14\u0e32\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001019 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e08\u0e34\u0e19\u0e14\u0e32\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 2569-07-16 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 98\/8  \u0e16\u0e19\u0e19\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0803569001027\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e21\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001027 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e21\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-16 1000000 10309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e25\u0e49\u0e32\u0e07 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e16\u0e19\u0e2d\u0e21\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 188  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002734\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0b \u0e25\u0e34\u0e07\u0e01\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002734 \u0e1a\u0e08.\u0e44\u0e0b \u0e25\u0e34\u0e07\u0e01\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e08\u0e34\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 147\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0815569002106\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e1a\u0e35.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e19\u0e17\u0e23 2022 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002106 \u0e1a\u0e08.\u0e40\u0e04.\u0e1a\u0e35.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e19\u0e17\u0e23 2022 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 126\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0825569001169\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001169 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 29\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569013205\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013205 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22  \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04  \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013230\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e33\u0e1b\u0e31\u0e49\u0e1998 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013230 \u0e1a\u0e08.\u0e01\u0e33\u0e1b\u0e31\u0e49\u0e1998 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u60c5\u5831\u901a\u4fe1\u30fbit 48\/178  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0843569001353\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001353 \u0e2b\u0e08.\u0e1a\u0e35\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 2569-07-16 1000000 77301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 161  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0843569001370\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a-\u0e42\u0e2e\u0e21 2006\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001370 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a-\u0e42\u0e2e\u0e21 2006 2569-07-16 1000000 55102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 247\/122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010460\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e25\u0e04\u0e15\u0e23\u0e49\u0e32 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27103\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27103\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010460 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e25\u0e04\u0e15\u0e23\u0e49\u0e32 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 27103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 60\/280  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e23\u0e35\u0e19\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010478\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e33\u0e1b\u0e39\u0e21\u0e49\u0e32\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010478 \u0e1a\u0e08.\u0e22\u0e33\u0e1b\u0e39\u0e21\u0e49\u0e32\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 548\/10  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010494\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"53200\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"53200\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010494 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 53200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e19\u0e19\u0e32\u0e21 j&t express \u904b\u8f38\u30fb\u7269\u6d41 15\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005813\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005813 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e15\u0e39 pvc \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005821\",\"name_th\":\"\u0e1a\u0e08. \u0e15\u0e31\u0e07\u0e04\u0e4c\u0e40\u0e15\u0e47\u0e21\u0e40\u0e1b\u0e4b\u0e32\u0e15\u0e38\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005821 \u0e1a\u0e08. \u0e15\u0e31\u0e07\u0e04\u0e4c\u0e40\u0e15\u0e47\u0e21\u0e40\u0e1b\u0e4b\u0e32\u0e15\u0e38\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005848\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e17\u0e27\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005848 \u0e1a\u0e08.\u0e19\u0e32\u0e17\u0e27\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e0b\u0e31\u0e01\u0e2d\u0e1a\u0e1c\u0e49\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 211\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0915569000358\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e0b\u0e35 \u0e04\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85497\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85497\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0915569000358 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e0b\u0e35 \u0e04\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 85497 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e15\u0e4c \u0e43\u0e2b\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e0e\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u6559\u80b2 605  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0955569000595\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e21 2017 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000595 \u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e21 2017 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 663  \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e42\u0e23\u0e23\u0e2a \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007552\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e1b\u0e23\u0e42\u0e2e\u0e21 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007552 \u0e2b\u0e08.\u0e42\u0e1b\u0e23\u0e42\u0e2e\u0e21 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 2569-07-15 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/14  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e23\u0e32\u0e0a\u0e2a\u0e34\u0e17\u0e18\u0e32\u0e23\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007561\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e35\u0e22\u0e39\u0e2a \u0e40\u0e17\u0e23\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007561 \u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e23\u0e35\u0e22\u0e39\u0e2a \u0e40\u0e17\u0e23\u0e14 2569-07-15 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e02\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/14  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e23\u0e32\u0e0a\u0e2a\u0e34\u0e17\u0e18\u0e32\u0e23\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007579\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e39\u0e42\u0e21\u0e48 \u0e16\u0e38\u0e07\u0e08\u0e31\u0e01\u0e1e\u0e23\u0e23\u0e14\u0e34\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007579 \u0e2b\u0e08.\u0e0b\u0e39\u0e42\u0e21\u0e48 \u0e16\u0e38\u0e07\u0e08\u0e31\u0e01\u0e1e\u0e23\u0e23\u0e14\u0e34 2569-07-15 1000000 22220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u88fd\u9020 59  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007587\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e2a\u0e01\u0e34\u0e19 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e23\u0e39\u0e21\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96305\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96305\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007587 \u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e2a\u0e01\u0e34\u0e19 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e23\u0e39\u0e21 2569-07-15 1000000 96305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e2d\u0e1a\u0e19\u0e27\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 2\/8  \u0e0b\u0e2d\u0e22 \u0e09\u0e25\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07 53 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133401\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133401 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 68101 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u4e0d\u52d5\u7523 15  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e1419 \u0e41\u0e22\u0e0110 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133436\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e27\u0e15\u0e15\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133436 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e27\u0e15\u0e15\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2099\/264  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133444\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e19\u0e0a\u0e31\u0e19\u0e19\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133444 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e19\u0e0a\u0e31\u0e19\u0e19\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 319  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e32\u0e21\u0e08\u0e38\u0e23\u0e35\u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 24 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133452\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e19 \u0e41\u0e25\u0e49\u0e27 \u0e14\u0e35 \u0e40\u0e25\u0e34\u0e28  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133452 \u0e1a\u0e08.\u0e01\u0e34\u0e19 \u0e41\u0e25\u0e49\u0e27 \u0e14\u0e35 \u0e40\u0e25\u0e34\u0e28  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e49\u0e33\u0e1b\u0e31\u0e48\u0e19 \u0e2a\u0e21\u0e39\u0e17\u0e15\u0e35\u0e49 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 756\/83  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133461\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32 \u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e34\u0e0b\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133461 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e35\u0e19\u0e48\u0e32 \u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e34\u0e0b\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1b\u0e31\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 209\/15  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133479\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e19\u0e42\u0e15\u0e1f\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133479 \u0e1a\u0e08.\u0e40\u0e1f\u0e19\u0e42\u0e15\u0e1f\u0e2d\u0e19\u0e15\u0e31\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30 \u60c5\u5831\u901a\u4fe1\u30fbit 1\/89  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e32\u0e0b\u0e48\u0e32\u0e40\u0e25\u0e40\u0e08\u0e49\u0e19\u0e17\u0e4c\u0e40\u0e01\u0e29\u0e15\u0e23\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 14 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133487\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e40\u0e2d\u0e21\u0e27\u0e35 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55901\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55901\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133487 \u0e1a\u0e08.\u0e40\u0e40\u0e2d\u0e21\u0e27\u0e35 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 55901 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 1158  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1922 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133509\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e34\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e25\u0e34\u0e15\u0e34\u0e40\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133509 \u0e1a\u0e08.\u0e04\u0e23\u0e34\u0e21\u0e34\u0e19\u0e2d\u0e25 \u0e25\u0e34\u0e15\u0e34\u0e40\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 21\/5  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133517\",\"name_th\":\"\u0e1a\u0e08. \u0e21\u0e34\u0e49\u0e19\u0e27\u0e48\u0e32\u0e14\u0e35\u0e22\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133517 \u0e1a\u0e08. \u0e21\u0e34\u0e49\u0e19\u0e27\u0e48\u0e32\u0e14\u0e35\u0e22\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 3  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 31 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133533\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e04\u0e4c\u0e01\u0e35\u0e49 \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133533 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e04\u0e4c\u0e01\u0e35\u0e49 \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c 111  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1988-1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133541\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133541 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c 111  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1988 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133568\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07\u0e04\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133568 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07\u0e04\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 289\/88  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e17\u0e32\u0e40\u0e19\u0e35\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133576\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e34\u0e13\u0e2b\u0e4c 156 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133576 \u0e1a\u0e08.\u0e15\u0e34\u0e13\u0e2b\u0e4c 156 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 251  \u0e0b\u0e2d\u0e22 \u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c 27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133584\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133584 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 181\/1  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133614\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e27\u0e35 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47731\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47731\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133614 \u0e1a\u0e08.\u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e27\u0e35 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47731 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e27\u0e48\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e27\u0e48\u0e19\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e43\u0e2a\u0e48\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e22\u0e32\u0e40\u0e0a\u0e47\u0e14\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/3  \u0e0b\u0e2d\u0e22 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c 9 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133631\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133631 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/1  \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 16 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133681\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e42\u0e19\u0e25\u0e34\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133681 \u0e1a\u0e08.\u0e42\u0e01\u0e42\u0e19\u0e25\u0e34\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e14\u0e23\u0e1f\u0e4c\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e23\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e40\u0e0a\u0e47\u0e04\u0e2a\u0e1b\u0e34\u0e14\u0e2a\u0e4c \u0e14\u0e39\u0e23\u0e30\u0e22\u0e30 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2d\u0e2d\u0e01\u0e23\u0e2d\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e15\u0e35\u0e01\u0e2d\u0e25\u0e4c\u0e1f\u0e14\u0e49\u0e27\u0e22\u0e42\u0e1b\u0e23\u0e2a\u0e2d\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u82b8\u8853\u30fb\u5a2f\u697d 7\/112  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133711\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e17\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46442\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46442\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133711 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e17\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46442 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e42\u0e23\u0e21\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e32\u0e1e\u0e35 (aromatherapy) \u0e01\u0e49\u0e32\u0e19\u0e44\u0e21\u0e49\u0e2b\u0e2d\u0e21\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e01\u0e25\u0e34\u0e48\u0e19 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e16\u0e38\u0e07\u0e2b\u0e2d\u0e21 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e09\u0e35\u0e14\u0e2b\u0e21\u0e2d\u0e19 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e19\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e25\u0e14\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e1a\u0e01\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e34\u0e14\u0e15\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e14\u0e1a\u0e31\u0e07\u0e41\u0e2a\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e38\u0e14\u0e2b\u0e39 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15\/173  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e48\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133738\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133738 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 5 \u0e41\u0e22\u0e01 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133754\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e2b\u0e23\u0e31\u0e10 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133754 \u0e1a\u0e08.\u0e2a\u0e2b\u0e23\u0e31\u0e10 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e16\u0e43\u0e2b\u0e21\u0e48\u0e1b\u0e49\u0e32\u0e22\u0e41\u0e14\u0e07\u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e42\u0e2d\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c  \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e49\u0e32\u0e22 \u0e04\u0e31\u0e14\u0e40\u0e25\u0e48\u0e21\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e2a\u0e25\u0e31\u0e1a\u0e40\u0e25\u0e02\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e2a\u0e07\u0e27\u0e19\u0e40\u0e25\u0e02\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 2823\/3  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133762\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 1988 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"15201\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"15201\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133762 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e17\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 1988 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 15201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e1b\u0e31\u0e49\u0e21\u0e42\u0e25\u0e42\u0e01\u0e49 \u0e15\u0e35\u0e15\u0e23\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2b\u0e19\u0e31\u0e07 \u0e1c\u0e49\u0e32 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u88fd\u9020 2823\/3  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133771\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e32-\u0e1e\u0e35\u0e23\u0e30 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133771 \u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e32-\u0e1e\u0e35\u0e23\u0e30 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/280  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133797\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133797 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e48\u0e07 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 212\/8  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133827\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e42\u0e15\u0e23\u0e19\u0e31\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10307\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10307\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133827 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e42\u0e15\u0e23\u0e19\u0e31\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 10307 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e16\u0e31\u0e48\u0e27 \u0e1e\u0e35\u0e41\u0e04\u0e19 \u0e2d\u0e31\u0e25\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1f\u0e31\u0e01\u0e17\u0e2d\u0e07 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e41\u0e15\u0e07\u0e42\u0e21 \u0e41\u0e21\u0e04\u0e04\u0e32\u0e40\u0e14\u0e40\u0e21\u0e35\u0e22 \u0e16\u0e31\u0e48\u0e27\u0e1e\u0e34\u0e2a\u0e15\u0e32\u0e0a\u0e34\u0e42\u0e2d \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u88fd\u9020 283\/39  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e2e\u0e21\u0e40\u0e1e\u0e25\u0e2a \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 18 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 55 (\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133835\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2a\u0e44\u0e17\u0e22\u0e1b\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133835 \u0e1a\u0e08.\u0e44\u0e2a\u0e44\u0e17\u0e22\u0e1b\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 56\/132  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 71 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133860\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e15\u0e49\u0e32\u0e40\u0e21\u0e14\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133860 \u0e1a\u0e08.\u0e14\u0e32\u0e15\u0e49\u0e32\u0e40\u0e21\u0e14\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (software) \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence) \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 (nursing home) \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u60c5\u5831\u901a\u4fe1\u30fbit 54\/76  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e2a\u0e34\u0e23\u0e34 \u0e1e\u0e2b\u0e25-\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133908\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e0a\u0e39\u0e23\u0e35\u0e48 \u0e41\u0e2e\u0e23\u0e4c \u0e0b\u0e32\u0e25\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133908 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e0a\u0e39\u0e23\u0e35\u0e48 \u0e41\u0e2e\u0e23\u0e4c \u0e0b\u0e32\u0e25\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e23\u0e07\u0e1c\u0e21  \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e30 \u0e41\u0e15\u0e48\u0e07 \u0e15\u0e31\u0e14 \u0e40\u0e0b\u0e47\u0e17 \u0e22\u0e49\u0e2d\u0e21\u0e2a\u0e35 \u0e41\u0e15\u0e48\u0e07\u0e2a\u0e35 \u0e14\u0e31\u0e14 \u0e22\u0e37\u0e14\u0e1c\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 68\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 bnn park  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a 05 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133916\",\"name_th\":\"\u0e1a\u0e08. \u0e01\u0e31\u0e19\u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 365  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133916 \u0e1a\u0e08. \u0e01\u0e31\u0e19\u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 365  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/457  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e34\u0e15\u0e15\u0e34\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e27\u0e25\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133924\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133924 \u0e1a\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21 \u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e07\u0e34\u0e19\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e2b\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 27\/457  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e34\u0e15\u0e15\u0e34\u0e0a\u0e31\u0e22 \u0e27\u0e34\u0e27\u0e25\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133941\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e01\u0e23\u0e23\u0e27\u0e35 \u0e1f\u0e39\u0e4899 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133941 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e01\u0e23\u0e23\u0e27\u0e35 \u0e1f\u0e39\u0e4899 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 80  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134017\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e2d\u0e35 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134017 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e2d\u0e35 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 150  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e40\u0e1e\u0e25\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1701\/3 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 55 (\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134033\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e1926 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134033 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e1926 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e23\u0e49\u0e32\u0e19\u0e17\u0e33\u0e1c\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e1b\u0e32 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e14\u0e39\u0e41\u0e25\u0e40\u0e25\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 288\/67  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134041\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1a\u0e35 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134041 \u0e1a\u0e08.\u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1a\u0e35 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e14\u0e35\u0e1a\u0e38\u0e01 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e19\u0e34\u0e40\u0e01\u0e34\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/129  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 23\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134050\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134050 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (marketplace) \u0e42\u0e0b\u0e40\u0e0b\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7\/2  \u0e0b\u0e2d\u0e22 \u0e41\u0e2a\u0e21\u0e14\u0e3317 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134068\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e39\u0e1f\u0e39 \u0e40\u0e1a\u0e04\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134068 \u0e1a\u0e08.\u0e1f\u0e39\u0e1f\u0e39 \u0e40\u0e1a\u0e04\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\/\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 221  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134076\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134076 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 18\/198  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 60 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134092\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e27\u0e34\u0e25 \u0e21\u0e39\u0e1f\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134092 \u0e1a\u0e08.\u0e17\u0e27\u0e34\u0e25 \u0e21\u0e39\u0e1f\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u82b8\u8853\u30fb\u5a2f\u697d 2994,2996  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1e\u0e17\u0e17\u0e34\u0e42\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 iv16 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134106\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e25\u0e35\u0e1f \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e48\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134106 \u0e1a\u0e08.\u0e42\u0e2d\u0e25\u0e35\u0e1f \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e48\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e41\u0e01\u0e07\u0e32\u0e21 13 \u0e41\u0e22\u0e01 4-1 \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134114\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134114 \u0e1a\u0e08.\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e30\u0e2a\u0e21 \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e44\u0e2d\u0e40\u0e17\u0e47\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e32\u0e22\u0e32\u0e01 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e1a\u0e39\u0e18 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 126   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1a-5 \u0e0b\u0e2d\u0e22 \u0e08\u0e38\u0e2c\u0e32 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134122\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134122 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e33\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5efa\u8a2d 2  \u0e0b\u0e2d\u0e22 \u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002470\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e31\u0e19 28 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002470 \u0e2b\u0e08.\u0e0b\u0e31\u0e19 28 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-15 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 123\/319  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e19\u0e32\u0e25\u0e35 35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023321\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e04\u0e34\u0e14  \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023321 \u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e04\u0e34\u0e14  \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e22\u0e01\u0e42\u0e23\u0e04 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e21\u0e35  \u0e2b\u0e49\u0e2d\u0e07\u0e17\u0e14\u0e25\u0e2d\u0e07  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e22\u0e32  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e17\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e32\u0e28\u0e08\u0e32\u0e01\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 99\/134  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023339\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a 8 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023339 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a 8 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e1a\u0e14\u0e21\u0e34\u0e19\u0e15\u0e31\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e01\u0e35\u0e2c\u0e32\u0e41\u0e1a\u0e14\u0e21\u0e34\u0e19\u0e15\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e35\u0e2c\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e35\u0e48 \u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e04\u0e48\u0e32\u0e22\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 177\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e2d \u0e27\u0e31\u0e19 \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023347\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e07\u0e1b\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023347 \u0e1a\u0e08.\u0e14\u0e07\u0e1b\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e2d\u0e19\u0e38\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e39 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 446  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023355\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e34\u0e13\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e04\u0e49\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023355 \u0e1a\u0e08.\u0e13\u0e34\u0e13\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e04\u0e49\u0e32\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e21\u0e49\u0e41\u0e1a\u0e1a\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e44\u0e21\u0e49\u0e2d\u0e31\u0e14 \u0e44\u0e21\u0e49\u0e1e\u0e32\u0e40\u0e25\u0e17 \u0e44\u0e21\u0e49\u0e40\u0e01\u0e48\u0e32\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e44\u0e21\u0e49\u0e2a\u0e19\u0e19\u0e2d\u0e01 \u0e44\u0e21\u0e49\u0e09\u0e33\u0e09\u0e32 \u0e44\u0e21\u0e49\u0e22\u0e32\u0e07 \u88fd\u9020 47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023363\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e25\u0e35\u0e22\u0e19\u0e2e\u0e27\u0e32\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023363 \u0e1a\u0e08.\u0e40\u0e2b\u0e25\u0e35\u0e22\u0e19\u0e2e\u0e27\u0e32\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 50\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023371\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17 \u0e1a\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023371 \u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17 \u0e1a\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 (automation) \u0e41\u0e25\u0e30 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 (solution) \u88fd\u9020 33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023380\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 \u0e44\u0e17\u0e14\u0e4c \u0e14\u0e34\u0e2a\u0e17\u0e23\u0e34\u0e1a\u0e34\u0e27\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023380 \u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 \u0e44\u0e17\u0e14\u0e4c \u0e14\u0e34\u0e2a\u0e17\u0e23\u0e34\u0e1a\u0e34\u0e27\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 9\/154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023398\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023398 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u5efa\u8a2d 28\/153  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023401\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e35\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29302\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29302\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023401 \u0e1a\u0e08.\u0e2d\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e35\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 29302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 ( ev) \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 300\/87  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2a\u0e19\u0e32\u0e01\u0e23\u0e35\u0e25\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1b\u0e25\u0e322 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023452\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023452 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023479\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e22\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e07\u0e04\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023479 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e22\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e07\u0e04\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e40\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e40\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e40\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1713\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026532\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 2529 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026532 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 2529 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 69200 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 100\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026559\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026559 \u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026567\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e35 \u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e1a\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026567 \u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e35 \u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e1a\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/224  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026575\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026575 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e22\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e22\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e22\u0e32\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026583\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e10\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026583 \u0e1a\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e10\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38\/590  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026591\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e25\u0e2a\u0e1b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026591 \u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e25\u0e2a\u0e1b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e43\u0e19\u0e23\u0e48\u0e21 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e34\u0e07\u0e25\u0e39\u0e01 \u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 116  \u0e2d\u0e32\u0e04\u0e32\u0e23sp2  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2\/5 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026605\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33131\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33131\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026605 \u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 33131 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e44\u0e2b\u0e21\u0e49 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32 \u0e2d\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e27\u0e32\u0e25\u0e4c\u0e27\u0e1b\u0e34\u0e14-\u0e40\u0e1b\u0e34\u0e14\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2b\u0e25\u0e2d\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e23\u0e2d\u0e1a\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u88fd\u9020 98\/283  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026621\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026621 \u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 22\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026630\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026630 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e0a\u0e48\u0e32 \u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 26\/369  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026699\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e40\u0e27\u0e17 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026699 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e40\u0e27\u0e17 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17(\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u60c5\u5831\u901a\u4fe1\u30fbit 15  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e3518\/1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021662\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e22\u0e07\u0e04\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021662 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e22\u0e07\u0e04\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e07\u0e44\u0e1b \u5efa\u8a2d 71\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021671\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e40\u0e0a\u0e19 \u0e1f\u0e23\u0e38\u0e15 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021671 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e40\u0e0a\u0e19 \u0e1f\u0e23\u0e38\u0e15 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021689\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e08\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021689 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e08\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e1e\u0e48\u0e07 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 68\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021697\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e2b\u0e21\u0e34\u0e15\u0e23 \u0e1f\u0e35\u0e14 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021697 \u0e1a\u0e08.\u0e2a\u0e2b\u0e21\u0e34\u0e15\u0e23 \u0e1f\u0e35\u0e14 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021701\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e0a\u0e1e\u0e23789 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021701 \u0e1a\u0e08.\u0e01\u0e0a\u0e1e\u0e23789 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 28\/307  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021719\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e23\u0e2d\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021719 \u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e23\u0e2d\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118\/148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021735\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e21\u0e38 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021735 \u0e1a\u0e08.\u0e21\u0e34\u0e21\u0e38 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/352  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021778\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10771\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10771\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021778 \u0e1a\u0e08.\u0e42\u0e21\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 10771 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u88fd\u9020 64\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07 11 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021786\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e48\u0e07\u0e40\u0e1b\u0e32 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021786 \u0e1a\u0e08.\u0e2d\u0e31\u0e48\u0e07\u0e40\u0e1b\u0e32 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01-\u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/272  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021794\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d.\u0e1e\u0e35. \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021794 \u0e1a\u0e08.\u0e40\u0e2d.\u0e1e\u0e35. \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e07\u0e32\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e25\u0e42\u0e01\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34 \u0e1b\u0e49\u0e32\u0e22\u0e44\u0e27\u0e19\u0e34\u0e25 \u0e1b\u0e49\u0e32\u0e22\u0e2d\u0e30\u0e04\u0e23\u0e34\u0e25\u0e34\u0e04 \u0e1b\u0e49\u0e32\u0e22\u0e44\u0e1f\u0e19\u0e35\u0e2d\u0e2d\u0e19 \u0e1b\u0e49\u0e32\u0e22\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e42\u0e25\u0e2b\u0e30 \u0e1b\u0e49\u0e32\u0e22\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e1b\u0e49\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e44\u0e1f \u0e1b\u0e49\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e1b\u0e49\u0e32\u0e22\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e1b\u0e49\u0e32\u0e22 \u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e41\u0e1c\u0e07\u0e1c\u0e31\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e49\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 234\/268  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004628\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004628 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e17\u0e35\u0e1f \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 29309 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e32\u0e01\u0e22\u0e32\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e0b\u0e35\u0e25\u0e22\u0e32\u0e07 \u0e1b\u0e30\u0e40\u0e01\u0e47\u0e19\u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e23\u0e2d\u0e07\u0e41\u0e17\u0e48\u0e19 \u0e22\u0e32\u0e07\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01 \u0e17\u0e48\u0e2d\u0e22\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 223\/253  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e31\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004636\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22.\u0e42\u0e2d.\u0e40\u0e2d\u0e2a.\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004636 \u0e1a\u0e08.\u0e27\u0e32\u0e22.\u0e42\u0e2d.\u0e40\u0e2d\u0e2a.\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/4  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e44\u0e25\u0e40\u0e2a\u0e19\u0e32(\u0e02) \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004644\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e27\u0e19\u0e0a\u0e2d\u0e1a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004644 \u0e1a\u0e08.\u0e0a\u0e27\u0e19\u0e0a\u0e2d\u0e1a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 109\/427  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004652\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e0a\u0e31\u0e22 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004652 \u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e0a\u0e31\u0e22 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 47\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0195569002561\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e17\u0e33\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002561 \u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e17\u0e33\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 65\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037363\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037363 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e21\u0e42\u0e0a\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 34\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037380\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e21\u0e39\u0e40\u0e25\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037380 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e21\u0e39\u0e40\u0e25\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07  \u0e1e\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e25\u0e31\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e01\u0e01\u0e32\u0e23\u0e30 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 169\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037398\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e25\u0e35\u0e48 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037398 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e25\u0e35\u0e48 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e2d\u0e07\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 40\/270  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037401\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e2c\u0e40\u0e27\u0e25\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037401 \u0e1a\u0e08.\u0e2d\u0e35\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e2c\u0e40\u0e27\u0e25\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e14\u0e34\u0e2a\u0e42\u0e01\u0e49\u0e40\u0e17\u0e04 \u0e04\u0e25\u0e31\u0e1a \u0e1a\u0e32\u0e23\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e44\u0e19\u0e15\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e21\u0e36\u0e19\u0e40\u0e21\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 86\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037428\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21. \u0e42\u0e27\u0e25\u0e17\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037428 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21. \u0e42\u0e27\u0e25\u0e17\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 35\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009432\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e04\u0e39\u0e25\u0e32\u0e23\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009432 \u0e1a\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e04\u0e39\u0e25\u0e32\u0e23\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e21\u0e32\u0e17\u0e33\u0e01\u0e32\u0e23\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e2d\u0e31\u0e1b\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e19\u0e33\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e15\u0e49\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e02\u0e31\u0e49\u0e19\u0e2a\u0e39\u0e07 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e41\u0e07\u0e48\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 555  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009441\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e17\u0e39\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009441 \u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e17\u0e39\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 65\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0243569000689\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33122\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33122\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000689 \u0e2b\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-15 1000000 33122 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e07\u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01 \u88fd\u9020 17  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e42\u0e1e\u0e18\u0e34\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002039\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e38\u0e01\u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002039 \u0e1a\u0e08.\u0e21\u0e38\u0e01\u0e44\u0e17\u0e22 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e22\u0e30\u0e1d\u0e31\u0e07\u0e01\u0e25\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e02\u0e22\u0e30 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 457  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569002063\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e07\u0e29\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e28\u0e23\u0e35\u0e21\u0e2b\u0e32\u0e42\u0e1e\u0e18\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002063 \u0e1a\u0e08.\u0e27\u0e07\u0e29\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e28\u0e23\u0e35\u0e21\u0e2b\u0e32\u0e42\u0e1e\u0e18\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e21\u0e32\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002753\",\"name_th\":\"\u0e2b\u0e08.\u0e0a.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e22\u0e32\u0e07\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002753 \u0e2b\u0e08.\u0e0a.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e22\u0e32\u0e07 2569-07-15 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 185  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007307\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e1e\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007307 \u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e1e\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07-\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007323\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e04\u0e40\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007323 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e04\u0e40\u0e2d \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 182  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0325569001228\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e27\u0e19\u0e2a\u0e38\u0e02 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001228 \u0e1a\u0e08.\u0e0a\u0e27\u0e19\u0e2a\u0e38\u0e02 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0325569001236\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001236 \u0e1a\u0e08.\u0e18\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 92\/7  \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e23\u0e49\u0e32\u0e07 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0333569000688\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e22\u0e37\u0e19 \u0e18\u0e32\u0e23\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000688 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e22\u0e37\u0e19 \u0e18\u0e32\u0e23\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-15 1000000 42901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u5efa\u8a2d 12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569001901\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e35\u0e4b\u0e40\u0e25\u0e47\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001901 \u0e2b\u0e08.\u0e15\u0e35\u0e4b\u0e40\u0e25\u0e47\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2569-07-15 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0355569000396\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0355569000396 \u0e1a\u0e08.\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e2a\u0e22\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e38\u0e14\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e16\u0e19\u0e19 led  \u0e0a\u0e38\u0e14\u0e42\u0e04\u0e21\u0e44\u0e1f\u0e16\u0e19\u0e19\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c  \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e16\u0e19\u0e19\u0e17\u0e48\u0e2d\u0e25\u0e2d\u0e14\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u5efa\u8a2d 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0385569000485\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000485 \u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e14\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e38\u0e4b\u0e22 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e25\u0e27\u0e14 \u0e08\u0e2d\u0e01\u0e22\u0e32\u0e07 \u0e16\u0e49\u0e27\u0e22\u0e22\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e21\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 231  \u0e2d\u0e32\u0e04\u0e32\u0e23-- \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003147\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e25\u0e32\u0e01\u0e23\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003147 \u0e2b\u0e08.\u0e0a\u0e25\u0e32\u0e01\u0e23\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 2569-07-15 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003171\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e32\u0e21\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e30\u0e1e\u0e32\u0e23\u0e4c\u0e40\u0e23\u0e25\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003171 \u0e2b\u0e08.\u0e25\u0e32\u0e21\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e30\u0e1e\u0e32\u0e23\u0e4c\u0e40\u0e23\u0e25 2569-07-15 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30 \u0e23\u0e31\u0e1a\u0e21\u0e32\u0e08\u0e32\u0e01\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/329  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006873\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006873 \u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006881\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e22\u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006881 \u0e1a\u0e08.\u0e19\u0e32\u0e22\u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e19\u0e27\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e40\u0e0a\u0e34\u0e49\u0e15 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e41\u0e08\u0e47\u0e01\u0e40\u0e01\u0e47\u0e15 \u0e2b\u0e21\u0e27\u0e01 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003688\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003688 \u0e1a\u0e08.\u0e42\u0e01 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e21\u0e31\u0e17\u0e09\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e08\u0e32\u0e01\u0e21\u0e31\u0e17\u0e09\u0e30 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e21\u0e31\u0e17\u0e09\u0e30 \u5bbf\u6cca\u30fb\u98f2\u98df 99\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e19\u0e32\u0e40\u0e01\u0e25\u0e37\u0e2d \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003696\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d \u0e1e\u0e23\u0e2d\u0e21\u0e21\u0e34\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003696 \u0e1a\u0e08.\u0e44\u0e2d \u0e1e\u0e23\u0e2d\u0e21\u0e21\u0e34\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 640\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0425569000522\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e39\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000522 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e39\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e32\u0e23\u0e01\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01  \u0e1c\u0e49\u0e32\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e37\u0e49\u0e2d\u0e19 \u0e1c\u0e49\u0e32\u0e2d\u0e49\u0e2d\u0e21 \u0e1c\u0e49\u0e32\u0e2b\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e40\u0e14\u0e47\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0445569001723\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e23\u0e34\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001723 \u0e1a\u0e08.\u0e14\u0e32\u0e23\u0e34\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e2a\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38\u0e41\u0e25\u0e30\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e27\u0e34\u0e17\u0e22\u0e38\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e15\u0e31\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e01\u0e31\u0e19\u0e02\u0e42\u0e21\u0e22\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e41\u0e08\u0e49\u0e07\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e15\u0e40\u0e27\u0e22\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32\u0e40\u0e23\u0e14 (\u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e35\u0e42\u0e21\u0e17\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 218,220  \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0455569001481\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e2a\u0e40\u0e15\u0e15\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001481 \u0e1a\u0e08.\u0e44\u0e2d\u0e2a\u0e40\u0e15\u0e15\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 355  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e22\u0e1e\u0e32\u0e2a\u0e42\u0e1e\u0e19\u0e17\u0e2d\u0e07 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001499\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32 \u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001499 \u0e1a\u0e08.\u0e14\u0e32 \u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e07\u0e34\u0e19 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e21\u0e38\u0e01 \u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e01\u0e34\u0e4a\u0e1a\u0e15\u0e34\u0e14\u0e1c\u0e21 \u0e17\u0e35\u0e48\u0e04\u0e32\u0e14\u0e1c\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e28\u0e35\u0e23\u0e29\u0e30 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0475569001553\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e41\u0e0b\u0e1a\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e27\u0e19\u0e31\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001553 \u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e41\u0e0b\u0e1a\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e27\u0e19\u0e31\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 233  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004932\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e19\u0e31\u0e0a\u0e0d\u0e4c\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e19\u0e2a\u0e48\u0e07\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"53200\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"53200\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004932 \u0e2b\u0e08.\u0e1b\u0e19\u0e31\u0e0a\u0e0d\u0e4c\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e19\u0e2a\u0e48\u0e07 2569-07-15 1000000 53200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 93  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004959\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e23\u0e2d\u0e22\u0e40\u0e14\u0e2d\u0e23\u0e35\u0e48\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"13999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"13999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004959 \u0e2b\u0e08.\u0e1e\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e23\u0e2d\u0e22\u0e40\u0e14\u0e2d\u0e23\u0e35\u0e48 2569-07-15 1000000 13999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e2e\u0e19\u0e14\u0e4c\u0e40\u0e21\u0e14 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 playworks \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e02\u0e2d\u0e07\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u88fd\u9020 112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015901\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e1f\u0e34\u0e2a\u0e34\u0e42\u0e2d \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86902\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86902\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015901 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e1f\u0e34\u0e2a\u0e34\u0e42\u0e2d \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 86902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u533b\u7642\u30fb\u798f\u7949 93\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015910\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e25\u0e35\u0e48 \u0e40\u0e1a\u0e0b\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015910 \u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e25\u0e35\u0e48 \u0e40\u0e1a\u0e0b\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 29  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e2b\u0e31\u0e2a\u0e14\u0e34\u0e40\u0e2a\u0e27\u0e35 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015928\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e41\u0e2d\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015928 \u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e41\u0e2d\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 69200 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 116\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015936\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015936 \u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e42\u0e17\u0e23\u0e19\u0e34\u0e04 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/1  \u0e16\u0e19\u0e19\u0e23\u0e16\u0e44\u0e1f \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015961\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e2a\u0e40\u0e1b\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015961 \u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e2a\u0e40\u0e1b\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 88\/151  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015987\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e0b\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015987 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e0b\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 630\/142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001412\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001412 \u0e1a\u0e08.\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e31\u0e01 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e1a\u0e1c\u0e49\u0e32 \u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001429\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e49\u0e27\u0e22\u0e04\u0e34\u0e07 \u0e1e\u0e35.\u0e0b\u0e35.\u0e40\u0e04. \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001429 \u0e2b\u0e08.\u0e2b\u0e49\u0e27\u0e22\u0e04\u0e34\u0e07 \u0e1e\u0e35.\u0e0b\u0e35.\u0e40\u0e04. \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-15 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e07\u0e32\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u5efa\u8a2d 579  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0535569000777\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e07\u0e04\u0e4c\u0e1f\u0e49\u0e32 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000777 \u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e07\u0e04\u0e4c\u0e1f\u0e49\u0e32 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0545569000793\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e2d\u0e21\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000793 \u0e1a\u0e08.\u0e2b\u0e2d\u0e21\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (reviewer) \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14 (influencer) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0545569000807\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e34\u0e2a \u0e27\u0e34\u0e04\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000807 \u0e1a\u0e08.\u0e1a\u0e25\u0e34\u0e2a \u0e27\u0e34\u0e04\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 68\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0545569000815\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000815 \u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u5efa\u8a2d 69\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0573569002204\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002204 \u0e2b\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-15 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e44\u0e21\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 503\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004578\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e49\u0e32 \u0e04\u0e34\u0e27 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004578 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e49\u0e32 \u0e04\u0e34\u0e27 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46441 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e22\u0e32 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 194  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004586\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e2d\u0e1f\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004586 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e2d\u0e1f\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 210  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001614\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e1e\u0e31\u0e15\u0e23\u0e4c 2557\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001614 \u0e2b\u0e08.\u0e1e\u0e23\u0e1e\u0e31\u0e15\u0e23\u0e4c 2557 2569-07-15 1000000 46209 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30 \u0e02\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001622\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e1e\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001622 \u0e2b\u0e08.\u0e41\u0e1e\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 2569-07-15 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e2a\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 75\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002035\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e25\u0e2d\u0e27\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002035 \u0e1a\u0e08.\u0e17\u0e35 \u0e25\u0e2d\u0e27\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e28\u0e32\u0e25 \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e42\u0e15\u0e15\u0e38\u0e25\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002043\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002043 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e14\u0e49\u0e32\u0e19\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u533b\u7642\u30fb\u798f\u7949 919\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0615569000580\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e1a\u0e32\u0e23\u0e4c 298 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000580 \u0e1a\u0e08.\u0e22\u0e39\u0e1a\u0e32\u0e23\u0e4c 298 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5bbf\u6cca\u30fb\u98f2\u98df 121  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e01\u0e01\u0e32\u0e23\u0e14\u0e35 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0625569000784\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07 - \u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e44\u0e1a\u0e04\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000784 \u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07 - \u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e44\u0e1a\u0e04\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e1a\u0e34\u0e4a\u0e01\u0e44\u0e1a\u0e04\u0e4c \u0e02\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 147  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0633569000723\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1f\u0e2d\u0e25\u0e23\u0e48\u0e32\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e2d\u0e41\u0e01\u0e19\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000723 \u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e1f\u0e2d\u0e25\u0e23\u0e48\u0e32\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e2d\u0e41\u0e01\u0e19\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c 2569-07-15 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 9\/48  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0635569001462\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e35\u0e22\u0e07\u0e44\u0e01\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 (\u0e0a.\u0e17\u0e27\u0e35\u0e42\u0e0a\u0e04) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001462 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e35\u0e22\u0e07\u0e44\u0e01\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 (\u0e0a.\u0e17\u0e27\u0e35\u0e42\u0e0a\u0e04) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 479\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0645569000741\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e2d. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000741 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e2d. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e25\u0e27\u0e14\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21,\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14,\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e08\u0e32\u0e23\u0e30\u0e1a\u0e35\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0705569003201\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003201 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 30\/19  \u0e16\u0e19\u0e19\u0e41\u0e21\u0e49\u0e19\u0e23\u0e33\u0e25\u0e36\u0e01 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002654\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e01\u0e25\u0e14\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002654 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e01\u0e25\u0e14\u0e4c 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 286\/79  \u0e16\u0e19\u0e19\u0e41\u0e2a\u0e07\u0e0a\u0e39\u0e42\u0e15 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002662\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002662 \u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e19\u0e47\u0e2d\u0e15 \u0e2a\u0e01\u0e23\u0e39 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a \u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002123\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e1a\u0e32\u0e22 \u0e04\u0e25\u0e35\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002123 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e1a\u0e32\u0e22 \u0e04\u0e25\u0e35\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e01\u0e34\u0e48\u0e07\u0e44\u0e21\u0e49 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e2a\u0e27\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e19\u0e34\u0e04\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e21\u0e32\u0e25\u0e31\u0e22\u0e41\u0e21\u0e19(321) \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007117\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007117 \u0e1a\u0e08.\u0e21\u0e35\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e14\u0e47\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e14\u0e47\u0e01 \u0e1c\u0e49\u0e32\u0e2d\u0e49\u0e2d\u0e21 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e14\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 117\/23  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e2d\u0e42\u0e2e\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007141\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e0a\u0e23\u0e1e\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2025 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007141 \u0e1a\u0e08.\u0e1e\u0e0a\u0e23\u0e1e\u0e25 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2025 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 22\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007401\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e44\u0e2d\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007401 \u0e1a\u0e08.\u0e40\u0e04\u0e44\u0e2d\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 57\/308  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007419\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e19\u0e32 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007419 \u0e1a\u0e08.\u0e42\u0e21\u0e19\u0e32 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e2d\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (e-commerce) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007427\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e44\u0e1e\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007427 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e44\u0e1e\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 25\/360  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007435\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e42\u0e23\u0e01\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007435 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e42\u0e23\u0e01\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0775569003006\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e23\u0e48\u0e32 \u0e40\u0e08 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003006 \u0e1a\u0e08.\u0e0b\u0e32\u0e23\u0e48\u0e32 \u0e40\u0e08 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1a\u0e38\u0e1f\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e47\u0e2d\u0e1b\u0e1b\u0e35\u0e49 \u0e25\u0e32\u0e0b\u0e32\u0e14\u0e49\u0e32 \u0e44\u0e25\u0e19\u0e4c\u0e41\u0e21\u0e19 \u0e41\u0e01\u0e23\u0e47\u0e1b \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 10  \u0e16\u0e19\u0e19\u0e41\u0e19\u0e1a\u0e40\u0e04\u0e2b\u0e32\u0e2a\u0e19\u0e4c \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0803569001001\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25 \u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001001 \u0e2b\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25 \u0e0b\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-15 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 224\/17  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e1b\u0e32\u0e01\u0e19\u0e04\u0e23 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0833569000560\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e25\u0e2d\u0e1f\u0e15\u0e34\u0e04\u0e2d\u0e25\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0833569000560 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e25\u0e2d\u0e1f\u0e15\u0e34\u0e04\u0e2d\u0e25 2569-07-15 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46  \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013043\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21 \u0e04\u0e2d\u0e23\u0e31\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04\u0e49\u0e2a\u0e15\u0e4c \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013043 \u0e1a\u0e08.\u0e25\u0e39\u0e21 \u0e04\u0e2d\u0e23\u0e31\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04\u0e49\u0e2a\u0e15\u0e4c \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e17 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 215  \u0e16\u0e19\u0e19\u0e42\u0e04\u0e01\u0e15\u0e42\u0e19\u0e14 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013051\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e38\u0e01\u0e2d\u0e31\u0e19\u0e14\u0e32 99 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013051 \u0e1a\u0e08.\u0e21\u0e38\u0e01\u0e2d\u0e31\u0e19\u0e14\u0e32 99 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 18\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013086\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013086 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e42\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\/\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 111\/168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013094\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e42\u0e2e\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81293\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81293\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013094 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e42\u0e2e\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 81293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07 \u0e2b\u0e19\u0e39\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e23\u0e1a\u0e01\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e43\u0e19\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e16\u0e44\u0e1f \u0e40\u0e23\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 63\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013108\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e40\u0e08 \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013108 \u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e40\u0e08 \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 48\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013141\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013141 \u0e1a\u0e08.\u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e2a\u0e20\u0e32\u0e1e \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e04\u0e32\u0e30 \u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0843569001345\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e19\u0e41\u0e21\u0e47\u0e04 \u0e0a\u0e49\u0e2d\u0e1b\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001345 \u0e2b\u0e08.\u0e27\u0e34\u0e19\u0e41\u0e21\u0e47\u0e04 \u0e0a\u0e49\u0e2d\u0e1b 2569-07-15 1000000 47190 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e2d\u0e17\u0e35 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010419\",\"name_th\":\"\u0e1a\u0e08.66 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010419 \u0e1a\u0e08.66 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 195\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010427\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e33\u0e19\u0e31\u0e19\u0e40\u0e2b\u0e21\u0e01\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010427 \u0e1a\u0e08.\u0e01\u0e33\u0e19\u0e31\u0e19\u0e40\u0e2b\u0e21\u0e01\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e15\u0e47\u0e19\u0e17\u0e4c\u0e42\u0e14\u0e21 \u0e40\u0e15\u0e47\u0e19\u0e17\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 76\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010451\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e35\u0e27\u0e32 65 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010451 \u0e1a\u0e08.\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e35\u0e27\u0e32 65 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e49\u0e01 \u0e04\u0e38\u0e01\u0e01\u0e35\u0e49 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 144\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005775\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e41\u0e2d\u0e25\u0e1f\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46594\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46594\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005775 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e41\u0e2d\u0e25\u0e1f\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 46594 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e14\u0e35\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e08\u0e32\u0e30\u0e23\u0e39  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e34\u0e14\u0e40\u0e25\u0e02 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e34\u0e14\u0e40\u0e07\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/4  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e20\u0e39\u0e27\u0e19\u0e32\u0e23\u0e16 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005791\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e01\u0e32\u0e42\u0e2d \u0e44\u0e17\u0e22 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005791 \u0e1a\u0e08.\u0e2e\u0e32\u0e01\u0e32\u0e42\u0e2d \u0e44\u0e17\u0e22 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e16\u0e19\u0e2d\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e40\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1c\u0e19\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u88fd\u9020 100\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005805\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005805 \u0e1a\u0e08.\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e38\u0e14\u0e19\u0e2d\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/119  \u0e16\u0e19\u0e19\u0e1c\u0e14\u0e38\u0e07\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0945569000731\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000731 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 82\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0103569007463\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1a\u0e35 \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007463 \u0e2b\u0e08.\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1a\u0e35 \u0e0a\u0e47\u0e2d\u0e1b 2569-07-14 1000000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u88fd\u9020 35\/16  \u0e0b\u0e2d\u0e22 \u0e40\u0e21\u0e15\u0e15\u0e32\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007471\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2d\u0e1a\u0e14\u0e34\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007471 \u0e2b\u0e08.\u0e42\u0e2d\u0e1a\u0e14\u0e34\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-14 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 21\/81  \u0e16\u0e19\u0e19\u0e17\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007480\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e31\u0e07\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007480 \u0e2b\u0e08.\u0e27\u0e31\u0e07\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 2569-07-14 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 111  \u0e0b\u0e2d\u0e22 \u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 4 \u0e16\u0e19\u0e19\u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007498\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e14\u0e35\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007498 \u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e14\u0e35 2569-07-14 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 111  \u0e0b\u0e2d\u0e22 \u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 4 \u0e16\u0e19\u0e19\u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007528\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2e\u0e42\u0e14\u0e23\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007528 \u0e2b\u0e08.\u0e44\u0e2e\u0e42\u0e14\u0e23\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-14 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04  \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19           \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 469\/12  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 39 (\u0e40\u0e17\u0e1e\u0e25\u0e35\u0e25\u0e32 1) \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132651\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132651 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e17\u0e32\u0e2a\u0e35 \u5efa\u8a2d 39\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132677\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e23\u0e39\u0e14\u0e49\u0e32  \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132677 \u0e1a\u0e08.\u0e01\u0e32\u0e23\u0e39\u0e14\u0e49\u0e32  \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 427\/7  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132685\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132685 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 10799 .\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 777\/99  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e35\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132707\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132707 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 30  \u0e0b\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e01\u0e2d\u0e07\u0e2a\u0e25\u0e32\u0e01 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132715\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e04\u0e42\u0e2d \u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132715 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e04\u0e42\u0e2d \u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 113\/2  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 75 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132740\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e40\u0e2d\u0e0a\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132740 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e40\u0e2d\u0e0a\u0e42\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 55\/95  \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e25\u0e33\u0e40\u0e08\u0e35\u0e22\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132774\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132774 \u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 66199 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e49\u0e2d\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e25\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e39\u0e01\u0e40\u0e1e\u0e34\u0e01\u0e16\u0e2d\u0e19\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e1f\u0e2d\u0e07\u0e0b\u0e34\u0e40\u0e2d\u0e23\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e08\u0e48\u0e32\u0e22\u0e42\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b \u91d1\u878d\u30fb\u4fdd\u967a 123  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e35.\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1202 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132782\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e25\u0e31\u0e1a. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132782 \u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e25\u0e31\u0e1a. \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56101 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e23\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 358  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e20\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132791\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e13\u0e31\u0e0e\u0e10\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132791 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e13\u0e31\u0e0e\u0e10\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9  \u0e16\u0e19\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e21\u0e2d\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132804\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e31\u0e19\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132804 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e31\u0e19\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 1203  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e0b\u0e32\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132812\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e2b\u0e34\u0e21\u0e30\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132812 \u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e2b\u0e34\u0e21\u0e30\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e42\u0e2d\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21\/\u0e42\u0e2d\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21 (oem\/odm) \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 489\/32  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132821\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e40\u0e27\u0e04 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132821 \u0e1a\u0e08.\u0e2d\u0e30\u0e40\u0e27\u0e04 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e25\u0e30\u0e04\u0e23\u0e40\u0e27\u0e17\u0e35 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e25\u0e30\u0e04\u0e23 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u82b8\u8853\u30fb\u5a2f\u697d 55\/94  \u0e16\u0e19\u0e1901 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132839\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e0a\u0e32\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132839 \u0e1a\u0e08.\u0e15\u0e23\u0e30\u0e01\u0e39\u0e25\u0e0a\u0e32\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 401  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c64 \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132871\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e0a\u0e32\u0e23\u0e4c\u0e08 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132871 \u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e0a\u0e32\u0e23\u0e4c\u0e08 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 100\/11  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132880\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e31\u0e1a\u0e1e\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132880 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e31\u0e1a\u0e1e\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e40\u0e01\u0e49\u0e32 43 (\u0e0b\u0e2d\u0e2221 \u0e40\u0e2a\u0e23\u0e354) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132898\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e40\u0e1a\u0e22\u0e4c 1988 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132898 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e40\u0e1a\u0e22\u0e4c 1988 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e2d\u0e42\u0e0b\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e2d\u0e42\u0e0b\u0e19\u0e19\u0e49\u0e33 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e22\u0e01\u0e01\u0e32\u0e01\u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43  \u0e0b\u0e2d\u0e22 \u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132901\",\"name_th\":\"\u0e1a\u0e08.\u0e13 \u0e17\u0e31\u0e28\u0e1e\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132901 \u0e1a\u0e08.\u0e13 \u0e17\u0e31\u0e28\u0e1e\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 39\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132910\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e32\u0e27 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132910 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e32\u0e27 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 54 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132936\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e19\u0e15\u0e15\u0e49\u0e32 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132936 \u0e1a\u0e08.\u0e14\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e19\u0e15\u0e15\u0e49\u0e32 \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27 \u0e44\u0e1b\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e02\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e2d\u0e19\u0e44\u0e0b\u0e15\u0e4c \u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 719  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e34\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 401 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e216 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132979\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132979 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 178\/2  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132995\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132995 \u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e08\u0e47\u0e1a\u0e1b\u0e48\u0e27\u0e22 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 134\/168  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 50 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133002\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e32\u0e40\u0e27\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133002 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e32\u0e40\u0e27\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e40\u0e20\u0e17 \u0e42\u0e06\u0e29\u0e13\u0e32 , \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 59\/9  \u0e0b\u0e2d\u0e22 \u0e08\u0e38\u0e2c\u0e32 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133037\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e2a\u0e27\u0e35\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133037 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e2a\u0e27\u0e35\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19 \u0e1e\u0e32\u0e22 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e02\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 61\/3   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133045\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e1f \u0e40\u0e1e\u0e47\u0e17 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133045 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e1f \u0e40\u0e1e\u0e47\u0e17 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/4  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133061\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133061 \u0e1a\u0e08.\u0e42\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e25\u0e21 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e19\u0e4d\u0e49\u0e32 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 275  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133070\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e0a\u0e1f\u0e2d\u0e23\u0e4c\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133070 \u0e1a\u0e08.\u0e41\u0e2d\u0e0a\u0e1f\u0e2d\u0e23\u0e4c\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e04\u0e4d\u0e32\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e4d\u0e32\u0e41\u0e19\u0e30\u0e19\u0e4d\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e31\u0e1a\u0e17\u0e4d\u0e32\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e17\u0e4d\u0e32\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e41\u0e25\u0e30\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e35 23 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133088\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e2d\u0e1a \u0e2b\u0e21\u0e2d\u0e01\u0e23\u0e39\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133088 \u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e2d\u0e1a \u0e2b\u0e21\u0e2d\u0e01\u0e23\u0e39\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 45\/15  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133096\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e22 \u0e40\u0e2d\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e1f \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133096 \u0e1a\u0e08.\u0e2e\u0e32\u0e22 \u0e40\u0e2d\u0e19 \u0e0b\u0e35 \u0e40\u0e2d\u0e1f \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u60c5\u5831\u901a\u4fe1\u30fbit 29\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1b\u0e34\u0e22\u0e30\u0e40\u0e1e\u0e25\u0e2a \u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e27\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 9a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133126\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e19\u0e04\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133126 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e19\u0e04\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 234\/8  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133193\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e27\u0e35 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133193 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e17\u0e27\u0e35 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/32  \u0e0b\u0e2d\u0e22 \u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d 1 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133223\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35\u0e04\u0e35\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59203\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59203\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133223 \u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35\u0e04\u0e35\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 59203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e1e\u0e25\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e23\u0e49\u0e2d\u0e07 \u0e17\u0e33\u0e19\u0e2d\u0e07 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e32\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e42\u0e19\u0e49\u0e15\u0e40\u0e1e\u0e25\u0e07 \u0e23\u0e27\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 2\/39  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 101 \u0e0b\u0e2d\u0e22 38 \u0e41\u0e22\u0e01 1 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133240\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e42\u0e21\u0e40\u0e27\u0e22\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133240 \u0e1a\u0e08.\u0e42\u0e2d\u0e42\u0e21\u0e40\u0e27\u0e22\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 719  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 23 \u0e42\u0e0b\u0e19 c \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133274\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e42\u0e23\u0e21\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133274 \u0e1a\u0e08.\u0e19\u0e34\u0e42\u0e23\u0e21\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e1b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e19\u0e19\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e02\u0e31\u0e14\u0e1c\u0e34\u0e27 \u0e19\u0e27\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a\u0e21\u0e37\u0e2d \u0e40\u0e25\u0e47\u0e1a\u0e40\u0e17\u0e49\u0e32 \u0e2a\u0e23\u0e30\u0e1c\u0e21  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e22\u0e25\u0e49\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e01\u0e14 \u0e01\u0e32\u0e23\u0e04\u0e25\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e35\u0e1a \u0e01\u0e32\u0e23\u0e14\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e04\u0e1a \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e15\u0e32\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 224\/227  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133291\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133291 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 4  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 58 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133355\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133355 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07  \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e01\u0e32\u0e22 \u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 82 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133363\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e1a\u0e2d\u0e19\u0e40\u0e17\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133363 \u0e1a\u0e08.\u0e2d\u0e35\u0e1a\u0e2d\u0e19\u0e40\u0e17\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 70201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e25\u0e2d\u0e1a\u0e1a\u0e35\u0e49 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 142\/15  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133371\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e04 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133371 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e04 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/32  \u0e0b\u0e2d\u0e22 \u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d 1 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133380\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e22\u0e32\u0e21 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133380 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e22\u0e32\u0e21 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/32  \u0e0b\u0e2d\u0e22 \u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d 1 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023240\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e27\u0e31\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2027 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023240 \u0e1a\u0e08.\u0e40\u0e2d \u0e27\u0e31\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2027 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 42909 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u5efa\u8a2d 177  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023258\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023258 \u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 68103 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u4e0d\u52d5\u7523 701  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023274\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023274 \u0e1a\u0e08.\u0e1e\u0e35\u0e42\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 111\/187  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023304\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023304 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e01\u0e25\u0e36\u0e07 \u0e23\u0e31\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e25\u0e2b\u0e30 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c (mold) \u0e41\u0e25\u0e30  \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e23\u0e31\u0e1a \u0e44\u0e2a \u0e40\u0e08\u0e32\u0e30 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e15\u0e31\u0e14 \u0e41\u0e15\u0e48\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e42\u0e25\u0e2b\u0e30 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c (die\/mold) \u88fd\u9020 711\/228  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026401\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e22\u0e42\u0e01\u0e23\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46314\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46314\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026401 \u0e1a\u0e08.\u0e42\u0e22\u0e42\u0e01\u0e23\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46314 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 128\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026419\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e34\u0e07\u0e14\u0e49\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026419 \u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e34\u0e07\u0e14\u0e49\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 96302 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e15\u0e31\u0e14\u0e02\u0e19 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e2a\u0e38\u0e19\u0e31\u0e02 \u0e41\u0e21\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07  \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 89\/129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026427\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026427 \u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22  \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e1d\u0e31\u0e07\u0e44\u0e21\u0e42\u0e04\u0e23\u0e0a\u0e34\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e09\u0e35\u0e14\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 79\/12,79\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026435\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026435 \u0e1a\u0e08.\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e39\u0e01\u0e02\u0e32\u0e14\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e41\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u9271\u696d\u30fb\u63a1\u77f3 73\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026443\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e17\u0e35\u0e1f \u0e2d\u0e35\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026443 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e17\u0e35\u0e1f \u0e2d\u0e35\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 10751 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u88fd\u9020 118\/112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026451\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e1f\u0e34\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026451 \u0e1a\u0e08.\u0e23\u0e35\u0e1f\u0e34\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e22\u0e34\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 (personal training) \u0e41\u0e25\u0e30\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e22\u0e04\u0e30 \u0e1e\u0e34\u0e25\u0e32\u0e17\u0e34\u0e2a \u0e40\u0e27\u0e17\u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e21\u0e27\u0e22\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e25\u0e32\u0e2a\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 99\/136  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026486\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e21\u0e41\u0e1e\u0e47\u0e04 \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026486 \u0e1a\u0e08.\u0e04\u0e2d\u0e21\u0e41\u0e1e\u0e47\u0e04 \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e0a\u0e33\u0e23\u0e30 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e34\u0e0a\u0e0a\u0e39\u0e48 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e0a\u0e47\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e0a\u0e47\u0e14\u0e21\u0e37\u0e2d \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e40\u0e0a\u0e47\u0e14\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e21\u0e49\u0e27\u0e19 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32 21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002445\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e1e\u0e1e\u0e4c\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002445 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e1e\u0e1e\u0e4c 2569-07-14 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 6\/340  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021565\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e39 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021565 \u0e1a\u0e08.\u0e0a\u0e39 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 136\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e16\u0e19\u0e19\u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021573\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e2a\u0e1b\u0e32\u0e22 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59122\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59122\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021573 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e2a\u0e1b\u0e32\u0e22 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 59122 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 81\/116  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021581\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2d\u0e34\u0e19\u0e0b\u0e39\u0e40\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021581 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e2d\u0e34\u0e19\u0e0b\u0e39\u0e40\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/177  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021590\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e42\u0e2d\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021590 \u0e1a\u0e08.\u0e14\u0e35\u0e42\u0e2d\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25 (telemedicine) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u533b\u7642\u30fb\u798f\u7949 2\/143  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 34\/1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021603\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021603 \u0e1a\u0e08.\u0e2a\u0e1b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 81\/136  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e34\u0e27\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021611\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e27\u0e4c\u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021611 \u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e27\u0e4c\u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 64\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021620\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e27\u0e32\u0e22\u0e1e\u0e35 \u0e40\u0e21\u0e14\u0e34 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021620 \u0e1a\u0e08.\u0e1e\u0e35\u0e27\u0e32\u0e22\u0e1e\u0e35 \u0e40\u0e21\u0e14\u0e34 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e33\u0e19\u0e33 \u0e42\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e14 \u0e46 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e0d\u52d5\u7523 40\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021638\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e2a\u0e31\u0e15\u0e22\u0e32 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021638 \u0e1a\u0e08.\u0e23\u0e31\u0e15\u0e2a\u0e31\u0e15\u0e22\u0e32 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 969\/511  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e31\u0e2a\u0e2a\u0e23 4 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021646\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e1e\u0e39\u0e19\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021646 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e1e\u0e39\u0e19\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e32\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e22\u0e32\u0e07\u0e23\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021654\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021654 \u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 147\/32  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 67 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004601\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e27\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004601 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e27\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0175569000479\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39 \u0e1e\u0e35 \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000479 \u0e1a\u0e08.\u0e22\u0e39 \u0e1e\u0e35 \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u8fb2\u6797\u6c34\u7523 140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000761\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2d\u0e21\u0e19\u0e34 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e27\u0e31\u0e19\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000761 \u0e2b\u0e08.\u0e42\u0e2d\u0e21\u0e19\u0e34 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e27\u0e31\u0e19 2569-07-14 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 107\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000779\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e19\u0e30 \u0e40\u0e1e\u0e47\u0e17 \u0e0a\u0e4a\u0e2d\u0e1b\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000779 \u0e2b\u0e08.\u0e21\u0e32\u0e19\u0e30 \u0e40\u0e1e\u0e47\u0e17 \u0e0a\u0e4a\u0e2d\u0e1b 2569-07-14 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 107\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002552\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e48\u0e27\u0e22 \u0e40\u0e07\u0e34\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002552 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e48\u0e27\u0e22 \u0e40\u0e07\u0e34\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e44\u0e16\u0e48\u0e16\u0e2d\u0e19 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e14 \u0e46 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e0d\u52d5\u7523 3\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003068\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35.\u0e40\u0e08.\u0e17\u0e35. \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003068 \u0e2b\u0e08.\u0e1e\u0e35.\u0e40\u0e08.\u0e17\u0e35. \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-14 1000000 49339 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e40\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e1e\u0e48\u0e27\u0e07\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e23\u0e16\u0e22\u0e01 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u904b\u8f38\u30fb\u7269\u6d41 99\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003076\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e17\u0e35. \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003076 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e04.\u0e17\u0e35. \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-14 1000000 49334 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 225\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003084\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c 5\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66123\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66123\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003084 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e0a\u0e19\u0e08\u0e4c 5 2569-07-14 1000000 66123 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u91d1\u878d\u30fb\u4fdd\u967a 56\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003092\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e2d\u0e32\u0e23\u0e32\u0e21\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003092 \u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e2d\u0e32\u0e23\u0e32\u0e21 2569-07-14 1000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1c\u0e2a\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21 \u0e41\u0e1c\u0e48\u0e19\u0e1e\u0e37\u0e49\u0e19 \u0e17\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e1a\u0e48\u0e2d\u0e1e\u0e31\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 345\/117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037118\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e19\u0e2d\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037118 \u0e1a\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e19\u0e2d\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e0b\u0e14\u0e4c \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1c\u0e2a\u0e21 \u6559\u80b2 19\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037126\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e08\u0e49\u0e19\u0e15\u0e4c \u0e44\u0e17\u0e22 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037126 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e08\u0e49\u0e19\u0e15\u0e4c \u0e44\u0e17\u0e22 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037134\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e42\u0e1b\u0e23 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037134 \u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e42\u0e1b\u0e23 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 25\/264  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037151\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e23\u0e13\u0e4c\u0e1b\u0e27\u0e35 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037151 \u0e1a\u0e08.\u0e20\u0e23\u0e13\u0e4c\u0e1b\u0e27\u0e35 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 22\/483  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037215\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037215 \u0e1a\u0e08.\u0e08\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 96309 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e44\u0e17\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 12\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037266\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e21\u0e40\u0e1a\u0e25 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037266 \u0e1a\u0e08.\u0e14\u0e31\u0e21\u0e40\u0e1a\u0e25 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 32309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e14\u0e31\u0e21\u0e40\u0e1a\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u88fd\u9020 21\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037274\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e14\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037274 \u0e1a\u0e08.\u0e41\u0e0b\u0e14\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38-\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037282\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037282 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 123\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009351\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e38\u0e49\u0e19 \u0e1b\u0e38\u0e49\u0e19 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009351 \u0e1a\u0e08.\u0e1b\u0e38\u0e49\u0e19 \u0e1b\u0e38\u0e49\u0e19 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36  \u0e16\u0e19\u0e19\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003809\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e19\u0e48\u0e32 \u0e14\u0e31\u0e2a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003809 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e19\u0e48\u0e32 \u0e14\u0e31\u0e2a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 70209 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 16\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0303569002737\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"61109\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"61109\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002737 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19 2569-07-14 1000000 61109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e2a\u0e32\u0e22 \u0e41\u0e25\u0e30 \u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a \u0e2d\u0e19\u0e32\u0e25\u0e47\u0e2d\u0e01 \u0e41\u0e25\u0e30 \u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22 \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e41\u0e25 \u0e30\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007277\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2014 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007277 \u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2014 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56101 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 101\/36  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e4 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007293\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e40\u0e19\u0e47\u0e04\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007293 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e40\u0e19\u0e47\u0e04\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 33200 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 automation , toolling, jig&fixture  \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17            \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 , \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 , \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 333\/455  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e13\u0e32\u0e2a\u0e23\u0e32 \u0e2d\u0e31\u0e25\u0e44\u0e1e\u0e19\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001899\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e19\u0e35\u0e48 \u0e42\u0e23\u0e1b \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81291\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81291\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001899 \u0e1a\u0e08.\u0e42\u0e17\u0e19\u0e35\u0e48 \u0e42\u0e23\u0e1b \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 81291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e16\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0333569000670\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000670 \u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e27\u0e34\u0e08\u0e34\u0e15\u0e23 2569-07-14 1000000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23 \u0e41\u0e21\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e2a\u0e38\u0e01\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u8fb2\u6797\u6c34\u7523 69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0345569003212\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e21\u0e32\u0e25\u0e35\u0e40\u0e19\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003212 \u0e1a\u0e08.\u0e2d\u0e21\u0e32\u0e25\u0e35\u0e40\u0e19\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 307\/91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003221\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10731\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10731\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003221 \u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 10731 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 294  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0403569003104\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 2569\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003104 \u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 2569 2569-07-14 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 469  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003112\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e34 \u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e34\u0e2a \u0e40\u0e23\u0e42\u0e27\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003112 \u0e2b\u0e08.\u0e14\u0e34 \u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e34\u0e2a \u0e40\u0e23\u0e42\u0e27\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-14 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 338  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003139\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003139 \u0e2b\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-14 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 281  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006741\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e2e\u0e31\u0e1a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006741 \u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e2e\u0e31\u0e1a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e2a\u0e25\u0e31\u0e1a av \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e15\u0e23\u0e07 (dc) \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 (normal charge) \u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 (quick charge) \u5efa\u8a2d 59\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006768\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a365 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006768 \u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a365 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u60c5\u5831\u901a\u4fe1\u30fbit 888\/77  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e2a\u0e1b\u0e23\u0e34\u0e07\u0e40\u0e1e\u0e25\u0e2a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006776\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e33\u0e1b\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006776 \u0e1a\u0e08.\u0e08\u0e33\u0e1b\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e32\u0e19\u0e42\u0e0a\u0e2b\u0e48\u0e27\u0e22\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e32\u0e21\u0e15\u0e23\u0e2d\u0e01 \u0e0b\u0e2d\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e02\u0e49\u0e32\u0e27 \u0e41\u0e1b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006814\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e2d\u0e19\u0e40\u0e14\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006814 \u0e1a\u0e08.\u0e27\u0e2d\u0e19\u0e40\u0e14\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003653\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003653 \u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 555\/78  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e0a\u0e22\u0e32 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e19\u0e32\u0e14\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003661\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e20\u0e31\u0e17\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07(2020) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003661 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e19\u0e20\u0e31\u0e17\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07(2020) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 561  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0435569001111\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001111 \u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 527  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0443569000831\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e2b\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2026\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000831 \u0e2b\u0e08.\u0e2a\u0e2b\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2026 2569-07-14 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e14\u0e34\u0e19 \u0e2b\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e17\u0e23\u0e32\u0e22\u0e1b\u0e19\u0e40\u0e1b\u0e37\u0e49\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0475569001529\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e27\u0e31\u0e13\u0e2c\u0e4c 145 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001529 \u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e27\u0e31\u0e13\u0e2c\u0e4c 145 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/14  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000913\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e0b\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e42\u0e04\u0e25\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000913 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e0b\u0e35 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e42\u0e04\u0e25\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e2a\u0e15\u0e23\u0e35 \u0e40\u0e14\u0e47\u0e01 \u0e40\u0e14\u0e47\u0e01\u0e2d\u0e48\u0e2d\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0503569004835\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004835 \u0e2b\u0e08.\u0e0a\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 2569-07-14 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 150  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004843\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2e\u0e25\u0e15\u0e35\u0e49 \u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e4c\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004843 \u0e2b\u0e08.\u0e40\u0e2e\u0e25\u0e15\u0e35\u0e49 \u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e4c 2569-07-14 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e25\u0e35\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 174\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004860\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e34\u0e23\u0e31\u0e0d\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004860 \u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e34\u0e23\u0e31\u0e0d 2569-07-14 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2b\u0e21\u0e48\u0e32\u0e25\u0e48\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e33 \u0e19\u0e33\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e1a\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e21\u0e35\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07 (\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01) \u5bbf\u6cca\u30fb\u98f2\u98df 356  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004878\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004878 \u0e2b\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-14 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004886\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004886 \u0e2b\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 2569-07-14 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004908\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e17\u0e23\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004908 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e17\u0e23\u0e14 2569-07-14 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004916\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22 2569\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004916 \u0e2b\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e44\u0e17\u0e22 2569 2569-07-14 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004924\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004924 \u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 2569-07-14 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015855\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015855 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c (\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c) \u5bbf\u6cca\u30fb\u98f2\u98df 267  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015871\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e1a\u0e2a \u0e01\u0e23\u0e39\u0e4a\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015871 \u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e1a\u0e2a \u0e01\u0e23\u0e39\u0e4a\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 78101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e1e\u0e25\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e23\u0e49\u0e2d\u0e07 \u0e17\u0e33\u0e19\u0e2d\u0e07 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e32\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e42\u0e19\u0e49\u0e15\u0e40\u0e1e\u0e25\u0e07 \u0e23\u0e27\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 200  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015898\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e2d\u0e30\u0e1a\u0e23\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015898 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e2d\u0e30\u0e1a\u0e23\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e08\u0e31\u0e14\u0e04\u0e48\u0e32\u0e22\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u6559\u80b2 99\/84  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001668\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 1982 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64991\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64991\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001668 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 1982 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 64991 \u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1a\u0e34\u0e01\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e34\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e08\u0e32\u0e01\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e21\u0e35 \u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a \u0e2d\u0e2d\u0e01 \u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e21\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e1f\u0e2d\u0e07\u0e0b\u0e34\u0e40\u0e2d\u0e23\u0e4c \u91d1\u878d\u30fb\u4fdd\u967a 288  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0555569000602\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e40\u0e27\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000602 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e40\u0e27\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e40\u0e27\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e04\u0e32\u0e23\u0e4c\u0e14\u0e34\u0e41\u0e01\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2e\u0e39\u0e49\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e31\u0e19\u0e2b\u0e19\u0e32\u0e27 \u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004543\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e25 99 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47512\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47512\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004543 \u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e25 99 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47512 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07\u0e1c\u0e49\u0e32\u0e2b\u0e48\u0e21 \u0e1c\u0e49\u0e32\u0e1b\u0e39\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19 \u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19 \u0e1b\u0e25\u0e2d\u0e01\u0e2b\u0e21\u0e2d\u0e19 \u0e1b\u0e25\u0e2d\u0e01\u0e1c\u0e49\u0e32\u0e19\u0e27\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 e-commerce \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 shopee, lazada, tiktok shop \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 744  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004560\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e15\u0e1f\u0e39\u0e1f\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004560 \u0e1a\u0e08.\u0e42\u0e15\u0e1f\u0e39\u0e1f\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 818  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001606\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e2a \u0e19\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001606 \u0e2b\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e2a \u0e19\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19 2569-07-14 1000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e0a\u0e19\u0e34\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30 \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0675569001497\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1e\u0e23\u0e40\u0e01\u0e23\u0e2a \u0e14\u0e23\u0e34\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42201\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42201\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001497 \u0e1a\u0e08.\u0e42\u0e1e\u0e23\u0e40\u0e01\u0e23\u0e2a \u0e14\u0e23\u0e34\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 42201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0675569001501\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e27\u0e23\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e082 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001501 \u0e1a\u0e08.\u0e1a\u0e27\u0e23\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e082 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 405  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0675569001519\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e17\u0e34\u0e27\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001519 \u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e17\u0e34\u0e27\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e38\u0e4b\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 350\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003189\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e38\u0e13\u0e13\u0e27\u0e34\u0e0a \u0e1f\u0e32\u0e23\u0e4c\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003189 \u0e1a\u0e08.\u0e1b\u0e38\u0e13\u0e13\u0e27\u0e34\u0e0a \u0e1f\u0e32\u0e23\u0e4c\u0e21  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 (\u0e2b\u0e21\u0e39\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002611\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002611 \u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002638\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e33\u0e2d\u0e49\u0e2d\u0e22 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002638 \u0e1a\u0e08.\u0e19\u0e49\u0e33\u0e2d\u0e49\u0e2d\u0e22 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30  \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 37\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002646\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e2a \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002646 \u0e1a\u0e08.\u0e41\u0e21\u0e2a \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e14 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e31\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 108,110  \u0e16\u0e19\u0e19\u0e41\u0e2a\u0e07\u0e0a\u0e39\u0e42\u0e15 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007109\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e30\u0e19\u0e3022 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007109 \u0e1a\u0e08.\u0e18\u0e30\u0e19\u0e3022 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 177\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0743569001001\",\"name_th\":\"\u0e2b\u0e08. \u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 2026\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569001001 \u0e2b\u0e08. \u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 2026 2569-07-14 1000000 22299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e09\u0e35\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u88fd\u9020 160\/414  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007371\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e1b\u0e15\u0e31\u0e19\u0e44\u0e1a\u0e04\u0e4c\u0e0a\u0e4a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45402\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45402\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007371 \u0e1a\u0e08.\u0e01\u0e31\u0e1b\u0e15\u0e31\u0e19\u0e44\u0e1a\u0e04\u0e4c\u0e0a\u0e4a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 45402 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e02\u0e2d\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007397\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007397 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 983\/189  \u0e16\u0e19\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0765569001461\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19\u0e1a\u0e34\u0e25\u0e14\u0e4c 2008 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001461 \u0e1a\u0e08.\u0e40\u0e19\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19\u0e1a\u0e34\u0e25\u0e14\u0e4c 2008 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0765569001470\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e25\u0e38\u0e4a\u0e04 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23941\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23941\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001470 \u0e1a\u0e08.\u0e1f\u0e25\u0e38\u0e4a\u0e04 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 23941 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c\u0e1c\u0e2a\u0e21\u0e40\u0e2a\u0e23\u0e47\u0e08 \u88fd\u9020 18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0803569000977\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000977 \u0e2b\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-14 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 93\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0803569000985\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000985 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-14 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569012951\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e27\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 1988 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012951 \u0e1a\u0e08.\u0e0a\u0e27\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 1988 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 179\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013001\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013001 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 27200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c  \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 101\/290  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013019\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93199\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93199\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013019 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e47\u0e01\u0e0b\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 93199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e25\u0e31\u0e1a\u0e01\u0e35\u0e2c\u0e32\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e01\u0e35\u0e2c\u0e32\u0e42\u0e22\u0e04\u0e30 \u0e01\u0e35\u0e2c\u0e32\u0e1e\u0e35\u0e23\u0e32\u0e17\u0e34\u0e2a \u0e01\u0e35\u0e2c\u0e32\u0e40\u0e15\u0e49\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e42\u0e23\u0e1a\u0e34\u0e04\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e41\u0e17\u0e23\u0e21\u0e42\u0e1e\u0e25\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e35\u0e2c\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010338\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010338 \u0e1a\u0e08.\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 4\/127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010354\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e13\u0e31\u0e0e\u0e0a\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010354 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e13\u0e31\u0e0e\u0e0a\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e02\u0e38\u0e14 \u0e23\u0e16\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23 \u0e23\u0e16\u0e41\u0e1a\u0e47\u0e01\u0e42\u0e2e \u0e23\u0e16\u0e15\u0e31\u0e01 \u0e23\u0e16\u0e40\u0e01\u0e23\u0e14 \u0e23\u0e16\u0e1a\u0e14 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 68\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010362\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e22 \u0e41\u0e2d\u0e14 \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010362 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e22 \u0e41\u0e2d\u0e14 \u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 79120 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 17\/112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0855569000537\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e25 \u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000537 \u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e25 \u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001223\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001223 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001231\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19 \u0e40\u0e0b\u0e32\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e25\u0e32\u0e40\u0e1a\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001231 \u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19 \u0e40\u0e0b\u0e32\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19 \u0e25\u0e32\u0e40\u0e1a\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e23\u0e32\u0e22\u0e32\u0e07 \u0e19\u0e32\u0e21\u0e1a\u0e31\u0e15\u0e23 \u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e49\u0e32\u0e22  \u0e1a\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14 \u0e1b\u0e49\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 136\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001240\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e21\u0e34 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001240 \u0e1a\u0e08.\u0e20\u0e39\u0e21\u0e34 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 43210 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 190  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e02\u0e32\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0925569001052\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e19\u0e33\u0e1e\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23921\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23921\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001052 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e19\u0e33\u0e1e\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000000 23921 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 383  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0103569007404\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007404 \u0e2b\u0e08.\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c 2569-07-13 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 21\/81  \u0e16\u0e19\u0e19\u0e17\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007412\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18\u0e25\u0e35\u0e48\u0e2d\u0e42\u0e01\u0e23\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007412 \u0e2b\u0e08.\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18\u0e25\u0e35\u0e48\u0e2d\u0e42\u0e01\u0e23 2569-07-13 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 111  \u0e0b\u0e2d\u0e22 \u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 4 \u0e16\u0e19\u0e19\u0e40\u0e14\u0e0a\u0e30\u0e15\u0e38\u0e07\u0e04\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007421\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e33\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007421 \u0e2b\u0e08.\u0e19\u0e33\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 2569-07-13 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 21\/81  \u0e16\u0e19\u0e19\u0e17\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007439\",\"name_th\":\"\u0e2b\u0e08. \u0e1e\u0e37\u0e0a\u0e17\u0e2d\u0e07\u0e04\u0e33\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007439 \u0e2b\u0e08. \u0e1e\u0e37\u0e0a\u0e17\u0e2d\u0e07\u0e04\u0e33 2569-07-13 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 21\/81  \u0e16\u0e19\u0e19\u0e17\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007447\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e37\u0e0a\u0e44\u0e17\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007447 \u0e2b\u0e08.\u0e1e\u0e37\u0e0a\u0e44\u0e17\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-13 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 21\/81  \u0e16\u0e19\u0e19\u0e17\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007455\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e25\u0e1b\u0e0a\u0e31\u0e22\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007455 \u0e2b\u0e08.\u0e28\u0e34\u0e25\u0e1b\u0e0a\u0e31\u0e22\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-13 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51  \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e1a\u0e39\u0e23\u0e1e\u0e32 17 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132090\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e42\u0e01\u0e23\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132090 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e42\u0e01\u0e23\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1111\/7  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132120\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e01\u0e4c\u0e21\u0e35\u0e14\u0e23\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132120 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e01\u0e4c\u0e21\u0e35\u0e14\u0e23\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/4  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 5 \u0e41\u0e22\u0e01 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132146\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e19\u0e34\u0e27\u0e32\u0e25 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132146 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e19\u0e34\u0e27\u0e32\u0e25 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 14112 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 121  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132171\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e1e\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132171 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e2d\u0e1e\u0e35\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e2d\u0e1f\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 34  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 26 \u0e41\u0e22\u0e01 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132189\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e04\u0e35\u0e22\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132189 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e04\u0e35\u0e22\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e40\u0e1b\u0e34\u0e14\u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e25\u0e47\u0e2d\u0e04 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 54 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132235\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d.\u0e40\u0e04.\u0e41\u0e2d\u0e25  \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e40\u0e25\u0e14\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132235 \u0e1a\u0e08.\u0e40\u0e2d.\u0e40\u0e04.\u0e41\u0e2d\u0e25  \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e40\u0e25\u0e14\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 69200 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e29\u0e35\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 18\/339  \u0e0b\u0e2d\u0e22 \u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c 39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132243\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e23\u0e34\u0e17\u0e31\u0e21 \u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132243 \u0e1a\u0e08.\u0e40\u0e21\u0e23\u0e34\u0e17\u0e31\u0e21 \u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u0e42\u0e2d\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e08\u0e32\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e0d\u52d5\u7523 989  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e04\u0e34\u0e07\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 45 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132251\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e49\u0e14 \u0e23\u0e35\u0e41\u0e25\u0e01\u0e0b\u0e4c \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132251 \u0e1a\u0e08.\u0e01\u0e39\u0e49\u0e14 \u0e23\u0e35\u0e41\u0e25\u0e01\u0e0b\u0e4c \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u533b\u7642\u30fb\u798f\u7949 98\/14  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 39 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132260\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e40\u0e2a\u0e48\u0e22 \u0e1f\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132260 \u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e40\u0e2a\u0e48\u0e22 \u0e1f\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e21\u0e31\u0e19\u0e44\u0e01\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 764  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132278\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e0a\u0e41\u0e17\u0e47\u0e01 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132278 \u0e1a\u0e08.\u0e41\u0e2e\u0e0a\u0e41\u0e17\u0e47\u0e01 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 242  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1c\u0e01\u0e32\u0e21\u0e32\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132286\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07 \u0e40\u0e2e\u0e07 \u0e42\u0e01\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132286 \u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07 \u0e40\u0e2e\u0e07 \u0e42\u0e01\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e14\u0e22\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e1b\u0e01\u0e15\u0e34\u0e08\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e2a\u0e39\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/181  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132316\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e34\u0e2a\u0e21\u0e32 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132316 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e34\u0e2a\u0e21\u0e32 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04\u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d \u0e27\u0e35\u0e14\u0e35\u0e42\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 70  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a48 \u0e41\u0e22\u0e0114-10 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132332\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10712\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10712\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132332 \u0e1a\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 10712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 112  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132341\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c \u0e2d\u0e35\u0e2a \u0e40\u0e17\u0e23\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132341 \u0e1a\u0e08.\u0e44\u0e17\u0e21\u0e4c \u0e2d\u0e35\u0e2a \u0e40\u0e17\u0e23\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47721 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/59  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132391\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132391 \u0e1a\u0e08.\u0e40\u0e08\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 141  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 19\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132405\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132405 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 939\/335  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132413\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32 \u0e27\u0e34\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132413 \u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32 \u0e27\u0e34\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (software) \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (automation) \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 198\/1  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132456\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e40\u0e25\u0e19\u0e17\u0e2d\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132456 \u0e1a\u0e08.\u0e01\u0e34\u0e40\u0e25\u0e19\u0e17\u0e2d\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (freight forwarder) \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e40\u0e23\u0e37\u0e2d \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e1a\u0e01 \u904b\u8f38\u30fb\u7269\u6d41 187\/57  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132481\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e1e\u0e35\u0e40\u0e2d\u0e0a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132481 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e1e\u0e35\u0e40\u0e2d\u0e0a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 15\/156  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e48\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132502\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132502 \u0e1a\u0e08.\u0e44\u0e2e\u0e25\u0e31\u0e01\u0e0b\u0e4c \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 42\/1 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132553\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132553 \u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e35 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e22\u0e22\u0e19\u0e15\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e 27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132561\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e42\u0e21\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45402\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45402\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132561 \u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e42\u0e21\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 45402 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e1c\u0e49\u0e32\u0e40\u0e1a\u0e23\u0e04 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 669  \u0e16\u0e19\u0e19\u0e2d\u0e42\u0e28\u0e01-\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132588\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e17\u0e35.\u0e17\u0e35 1979 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132588 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e17\u0e35.\u0e17\u0e35 1979 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 99\/16  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 41 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132600\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132600 \u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e25\u0e34\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e44\u0e17\u0e22 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (domestic tourism) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e02\u0e32\u0e40\u0e02\u0e49\u0e32 (inbound tourism) \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 208  \u0e2d\u0e32\u0e04\u0e32\u0e23208 \u0e41\u0e1a\u0e07\u0e04\u0e4a\u0e2d\u0e01  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1002 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132634\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e25\u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132634 \u0e1a\u0e08.\u0e0b\u0e35\u0e25\u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 54 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023207\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e40\u0e08\u0e19 \u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25 2895 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023207 \u0e1a\u0e08.\u0e23\u0e35\u0e40\u0e08\u0e19 \u0e21\u0e34\u0e23\u0e32\u0e40\u0e04\u0e34\u0e25 2895 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 599\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023215\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e21\u0e34\u0e40\u0e25\u0e34\u0e28\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023215 \u0e1a\u0e08.\u0e20\u0e39\u0e21\u0e34\u0e40\u0e25\u0e34\u0e28\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163  \u0e0b\u0e2d\u0e22 3(\u0e15\u0e23\u0e2d\u0e01\u0e16\u0e48\u0e32\u0e19) \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023223\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e1e\u0e32\u0e14\u0e32 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023223 \u0e1a\u0e08.\u0e19\u0e34\u0e1e\u0e32\u0e14\u0e32 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 43221 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01, \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32-\u0e02\u0e32\u0e22\u0e44\u0e1b, \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07-\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e14\u0e19\u0e49\u0e33, \u0e19\u0e49\u0e33\u0e2b\u0e22\u0e14, \u0e17\u0e48\u0e2d, \u0e1f\u0e34\u0e15\u0e15\u0e34\u0e49\u0e07, \u0e27\u0e32\u0e25\u0e4c\u0e27, \u0e1b\u0e31\u0e49\u0e21\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32, \u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19, \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21, \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 82\/315  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023231\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e172026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023231 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e172026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026265\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026265 \u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e39\u0e07\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 8 \u0e0a\u0e31\u0e49\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 91\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026281\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e04\u0e40\u0e0b\u0e2a \u0e25\u0e2d\u0e23\u0e4c\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026281 \u0e1a\u0e08.\u0e0b\u0e31\u0e04\u0e40\u0e0b\u0e2a \u0e25\u0e2d\u0e23\u0e4c\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 89\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026290\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e22\u0e34\u0e48\u0e07\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026290 \u0e1a\u0e08.\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e22\u0e34\u0e48\u0e07\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e39\u0e15\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e3532 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026303\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e352\u0e40\u0e2d\u0e2a \u0e1e\u0e34\u0e25\u0e42\u0e25\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46412\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46412\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026303 \u0e1a\u0e08.\u0e2d\u0e352\u0e40\u0e2d\u0e2a \u0e1e\u0e34\u0e25\u0e42\u0e25\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46412 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026311\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e1e\u0e38\u0e12\u0e34\u0e1e\u0e13\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026311 \u0e1a\u0e08.\u0e1e\u0e25\u0e1e\u0e38\u0e12\u0e34\u0e1e\u0e13\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14 \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e15\u0e23\u0e07 \u0e17\u0e32\u0e07\u0e2d\u0e49\u0e2d\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u0e0b\u0e35\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 189\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026338\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e21 \u0e0a\u0e49\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026338 \u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e21 \u0e0a\u0e49\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026354\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e1a\u0e35 \u0e42\u0e19\u0e27\u0e32\u0e44\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026354 \u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e1a\u0e35 \u0e42\u0e19\u0e27\u0e32\u0e44\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 78\/55  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e27\u0e31\u0e25\u0e40\u0e25\u0e22\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026362\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e01\u0e32\u0e42\u0e19 \u0e40\u0e1b\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82920\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82920\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026362 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e01\u0e32\u0e42\u0e19 \u0e40\u0e1b\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 82920 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 199\/56  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 70 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026371\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026371 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 52292 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e14\u0e49\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e01\u0e23\u0e21\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 75\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026389\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026389 \u0e1a\u0e08.\u0e1e\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e41\u0e01\u0e4a\u0e2a \u0e17\u0e48\u0e2d\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e17\u0e48\u0e2d\u0e19\u0e49\u0e33\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 21\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026397\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08999\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08999\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026397 \u0e1a\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e1b\u0e41\u0e15\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 08999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e39\u0e01\u0e02\u0e32\u0e14\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e41\u0e23\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e1a\u0e31\u0e15\u0e23\u0e1e\u0e34\u0e40\u0e28\u0e29 \u9271\u696d\u30fb\u63a1\u77f3 73\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021514\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1a\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021514 \u0e1a\u0e08.\u0e17\u0e35\u0e1a\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/60  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 34\/1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021522\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e04\u0e21\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e41\u0e04\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021522 \u0e1a\u0e08.\u0e40\u0e21\u0e04\u0e21\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e41\u0e04\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2a\u0e1b\u0e32 \u0e2a\u0e1b\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 31\/542  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021531\",\"name_th\":\"\u0e1a\u0e08.\u0e13 \u0e1a\u0e32\u0e07\u0e0a\u0e49\u0e32\u0e07 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021531 \u0e1a\u0e08.\u0e13 \u0e1a\u0e32\u0e07\u0e0a\u0e49\u0e32\u0e07 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 22\/42  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e14\u0e2d\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07- \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 89 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021549\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e04 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021549 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e04 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (e-commerce) \u0e0b\u0e36\u0e48\u0e07\u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04  \u0e22\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e22\u0e32\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e22\u0e32\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21  \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e19\u0e21\u0e1c\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004580\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e15\u0e35\u0e49\u0e21\u0e39\u0e48\u0e2b\u0e22\u0e32\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47899\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47899\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004580 \u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e15\u0e35\u0e49\u0e21\u0e39\u0e48\u0e2b\u0e22\u0e32\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47899 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e32\u0e23\u0e4c\u0e08  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001629\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001629 \u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 1\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0175569000461\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e25\u0e2a\u0e4c\u0e1e\u0e25\u0e31\u0e2a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2557 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000461 \u0e1a\u0e08.\u0e17\u0e39\u0e25\u0e2a\u0e4c\u0e1e\u0e25\u0e31\u0e2a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2557 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002544\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e1f\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e2a \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002544 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e1f\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e2a \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003041\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e35\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64999\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64999\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003041 \u0e2b\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e35 2569-07-13 1000000 64999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 38\/122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036871\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e08 \u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036871 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e08 \u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 131\/298  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036880\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35.\u0e22\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036880 \u0e1a\u0e08.\u0e27\u0e35.\u0e22\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 87301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u533b\u7642\u30fb\u798f\u7949 84\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e44\u0e23\u0e48\u0e01\u0e25\u0e49\u0e27\u0e22-\u0e19\u0e32\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036910\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e08\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036910 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e08\u0e40\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46900 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e27\u0e38\u0e18\u0e22\u0e38\u0e17\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2d\u0e32\u0e27\u0e38\u0e18\u0e1b\u0e37\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e38\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e14\u0e23\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01 \u0e0b\u0e49\u0e2d\u0e21\u0e22\u0e34\u0e07\u0e1b\u0e37\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e27\u0e38\u0e18\u0e1b\u0e37\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e2a\u0e38\u0e19\u0e1b\u0e37\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2d\u0e32\u0e27\u0e38\u0e18\u0e1b\u0e37\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 151\/304  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e31\u0e19\u0e17\u0e23\u0e35\u0e42\u0e2e\u0e21 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036928\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14938 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036928 \u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14938 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 120\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036936\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14235 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036936 \u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14235 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 120\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036961\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e42\u0e2d\u0e27\u0e32\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036961 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e42\u0e2d\u0e27\u0e32\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46201 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036979\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036979 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c,\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e23\u0e30\u0e22\u0e30\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c , \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 315\/1  \u0e16\u0e19\u0e19\u0e40\u0e1b\u0e23\u0e21\u0e43\u0e08\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036995\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e28\u0e34\u0e23\u0e34 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52299\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52299\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036995 \u0e1a\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e28\u0e34\u0e23\u0e34 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 52299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e39\u0e48\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e32\u0e01\u0e25 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e04\u0e39\u0e48\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u904b\u8f38\u30fb\u7269\u6d41 23\/60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037011\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e31\u0e19\u0e27\u0e32 \u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037011 \u0e1a\u0e08.\u0e20\u0e31\u0e19\u0e27\u0e32 \u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 3\/356  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037053\",\"name_th\":\"\u0e1a\u0e08.999 \u0e19\u0e32\u0e04\u0e23\u0e32\u0e0a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037053 \u0e1a\u0e08.999 \u0e19\u0e32\u0e04\u0e23\u0e32\u0e0a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 503\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037088\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e40\u0e14\u0e22\u0e4c \u0e1f\u0e39\u0e14\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037088 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e40\u0e14\u0e22\u0e4c \u0e1f\u0e39\u0e14\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e2b\u0e49\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001278\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e07\u0e2b\u0e25\u0e07 \u0e17\u0e30\u0e40\u0e25\u0e40\u0e1c\u0e32\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001278 \u0e2b\u0e08.\u0e08\u0e07\u0e2b\u0e25\u0e07 \u0e17\u0e30\u0e40\u0e25\u0e40\u0e1c\u0e32 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 174\/108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0213569001294\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"53200\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"53200\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001294 \u0e2b\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-13 1000000 53200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a \u0e2a\u0e48\u0e07 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 189\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0213569001308\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e17\u0e34\u0e15\u0e22\u0e32 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001308 \u0e2b\u0e08.\u0e2d\u0e17\u0e34\u0e15\u0e22\u0e32 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-13 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e31\u0e01 \u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009319\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e41\u0e2a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009319 \u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e41\u0e2a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 8\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002187\",\"name_th\":\"\u0e1a\u0e08.\u0e2a.\u0e28\u0e23\u0e35\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002187 \u0e1a\u0e08.\u0e2a.\u0e28\u0e23\u0e35\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a?\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002195\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002195 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 142\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0243569000671\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000671 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-13 1000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0275569001113\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e31\u0e17\u0e01\u0e23 \u0e42\u0e2e\u0e21\u0e41\u0e04\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01611\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01611\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001113 \u0e1a\u0e08.\u0e18\u0e19\u0e31\u0e17\u0e01\u0e23 \u0e42\u0e2e\u0e21\u0e41\u0e04\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 01611 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07 \u0e22\u0e32\u0e08\u0e38\u0e14\u0e01\u0e31\u0e19\u0e22\u0e38\u0e07 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e44\u0e25\u0e48\u0e22\u0e38\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u8fb2\u6797\u6c34\u7523 999  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0305569007234\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e23\u0e31\u0e0d\u0e0d\u0e20\u0e31\u0e17\u0e23\u0e4c 19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007234 \u0e1a\u0e08.\u0e27\u0e23\u0e31\u0e0d\u0e0d\u0e20\u0e31\u0e17\u0e23\u0e4c 19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 134  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001056\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e02\u0e19\u0e2a\u0e48\u0e07\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001056 \u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e02\u0e19\u0e2a\u0e48\u0e07 2569-07-13 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 38\/1  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e34\u0e15\u0e23 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0333569000661\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e24\u0e29\u0e18\u0e34\u0e0a\u0e3269\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000661 \u0e2b\u0e08.\u0e01\u0e24\u0e29\u0e18\u0e34\u0e0a\u0e3269 2569-07-13 1000000 47211 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 506  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569001897\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e20\u0e39\u0e1c\u0e32\u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001897 \u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e20\u0e39\u0e1c\u0e32\u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-13 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 205  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e02\u0e19\u0e31\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0353569000475\",\"name_th\":\"\u0e2b\u0e08.\u0e15.\u0e40\u0e08\u0e23\u0e34\u0e0d 2026\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000475 \u0e2b\u0e08.\u0e15.\u0e40\u0e08\u0e23\u0e34\u0e0d 2026 2569-07-13 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 236  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003091\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e44\u0e17\u0e22\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003091 \u0e2b\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e44\u0e17\u0e22\u0e1f\u0e39\u0e49\u0e14 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 888\/131  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e42\u0e2e\u0e21 \u0e21\u0e30\u0e25\u0e34\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006695\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e1b\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006695 \u0e1a\u0e08.\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e1b\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 shopee lazada tiktok \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157\/32  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e2b\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e1c\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006709\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2544 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006709 \u0e1a\u0e08.\u0e2d\u0e31\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2544 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 398\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003581\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e04 \u0e42\u0e0a\u0e04\u0e14\u0e35\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003581 \u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e04 \u0e42\u0e0a\u0e04\u0e14\u0e35\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47213 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 375  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003599\",\"name_th\":\"\u0e1a\u0e08.\u0e13.\u0e2d\u0e1a.999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003599 \u0e1a\u0e08.\u0e13.\u0e2d\u0e1a.999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e0d\u52d5\u7523 999  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32\u0e14\u0e35 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003611\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e44\u0e1b \u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003611 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e44\u0e1b \u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 82199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e17\u0e33\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e34\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 4\/26  \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e28\u0e23\u0e35 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0433569000423\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e39\u0e1e\u0e0d\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000423 \u0e2b\u0e08.\u0e20\u0e39\u0e1e\u0e0d\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-13 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 299  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0443569000792\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e2b\u0e2d\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000792 \u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e2b\u0e2d\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-13 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0443569000806\",\"name_th\":\"\u0e2b\u0e08.\u0e2a.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000806 \u0e2b\u0e08.\u0e2a.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 2569-07-13 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 215  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0443569000814\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000814 \u0e2b\u0e08.\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-13 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0453569001021\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e32\u0e1a\u0e39 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e21\u0e44\u0e1e\u0e23\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001021 \u0e2b\u0e08.\u0e0a\u0e32\u0e1a\u0e39 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e21\u0e44\u0e1e\u0e23\u0e4c 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e23\u0e49\u0e32\u0e19\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e34\u0e49\u0e21\u0e08\u0e38\u0e48\u0e21  \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e1a\u0e39  \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e38\u0e07\u0e02\u0e36\u0e49\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0453569001039\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e41\u0e1e\u0e2a\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001039 \u0e2b\u0e08.\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e41\u0e1e\u0e2a\u0e0a\u0e31\u0e48\u0e19 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 528  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0453569001047\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e42\u0e19\u0e42\u0e1f\u0e25\u0e35\u0e22\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001047 \u0e2b\u0e08.\u0e25\u0e39\u0e21\u0e34\u0e42\u0e19\u0e42\u0e1f\u0e25\u0e35\u0e22\u0e4c 2569-07-13 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001464\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001464 \u0e1a\u0e08.\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 72101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e2a\u0e34\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e4d\u0e49\u0e32\u0e1d\u0e19\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30(genius rain) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e2a\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 (\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e2a\u0e27\u0e19 \u0e44\u0e23\u0e48 \u0e19\u0e32 \u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35) \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14\u0e40\u0e17\u0e35\u0e22\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14\u0e40\u0e17\u0e35\u0e22\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1e\u0e37\u0e0a\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e19\u0e2d\u0e01\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e17\u0e35\u0e22\u0e21 (\u0e2b\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e02\u0e35\u0e49\u0e27\u0e31\u0e27,\u0e2b\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e02\u0e35\u0e49\u0e2b\u0e21\u0e39,\u0e2b\u0e31\u0e27\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e02\u0e35\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e32\u0e27) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 393\/11  \u0e16\u0e19\u0e19\u0e23\u0e13\u0e0a\u0e31\u0e22\u0e0a\u0e32\u0e0d\u0e22\u0e38\u0e17\u0e18 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0503569004738\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e21\u0e48\u0e32\u0e25\u0e48\u0e32 191 \u0e21\u0e2b\u0e32\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004738 \u0e2b\u0e08.\u0e2b\u0e21\u0e48\u0e32\u0e25\u0e48\u0e32 191 \u0e21\u0e2b\u0e32\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 134\/2  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e42\u0e01\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004754\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e23\u0e0b \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1f\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004754 \u0e2b\u0e08.\u0e40\u0e01\u0e23\u0e0b \u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1f 2569-07-13 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004762\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e32\u0e23\u0e4c\u0e41\u0e04\u0e23\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004762 \u0e2b\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e32\u0e23\u0e4c\u0e41\u0e04\u0e23\u0e4c 2569-07-13 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 70\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004789\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e42\u0e01\u0e25\u0e14\u0e4c\u0e40\u0e19\u0e2a\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004789 \u0e2b\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e42\u0e01\u0e25\u0e14\u0e4c\u0e40\u0e19\u0e2a 2569-07-13 1000000 47723 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7\/5  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004797\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e39\u0e01\u0e49\u0e32\u0e42\u0e0a\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004797 \u0e2b\u0e08.\u0e0a\u0e39\u0e01\u0e49\u0e32\u0e42\u0e0a 2569-07-13 1000000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e33 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004819\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e20\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47899\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47899\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004819 \u0e2b\u0e08.\u0e27\u0e34\u0e20\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-13 1000000 47899 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 235\/10  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e39\u0e48\u0e41\u0e14\u0e07 (\u0e09.81546) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015812\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e27\u0e1a\u0e2d\u0e2a\u0e40\u0e1b\u0e32\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015812 \u0e1a\u0e08.\u0e1a\u0e34\u0e27\u0e1a\u0e2d\u0e2a\u0e40\u0e1b\u0e32\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e23\u0e32\u0e14\u0e41\u0e01\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21  \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 109  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0535569000769\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000769 \u0e1a\u0e08.\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47213 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/49  \u0e0b\u0e2d\u0e22 15 \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e2d\u0e32\u0e2a\u0e19\u0e4c \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0565569000629\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e47\u0e15\u0e40\u0e17\u0e042026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000629 \u0e1a\u0e08.\u0e40\u0e01\u0e47\u0e15\u0e40\u0e17\u0e042026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e02\u0e49\u0e32\u0e07\u0e27\u0e31\u0e14\u0e01\u0e4a\u0e2d\u0e2b\u0e25\u0e27\u0e07 \u0e16\u0e19\u0e191093 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0575569004497\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e19\u0e34\u0e23\u0e31\u0e19\u0e14\u0e23\u0e4c 2012 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004497 \u0e1a\u0e08.\u0e1e\u0e23\u0e19\u0e34\u0e23\u0e31\u0e19\u0e14\u0e23\u0e4c 2012 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d\/\u0e21\u0e34\u0e19\u0e34\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004501\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e1b\u0e32\u0e16\u0e30 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004501 \u0e1a\u0e08.\u0e08\u0e34\u0e1b\u0e32\u0e16\u0e30 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 291  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004519\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e2b\u0e25\u0e07\u0e15\u0e34\u0e4a\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004519 \u0e1a\u0e08.\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e2b\u0e25\u0e07\u0e15\u0e34\u0e4a\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e0a\u0e38\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e0a\u0e38\u0e14\u0e0a\u0e32\u0e15\u0e34\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e1c\u0e49\u0e32\u0e1d\u0e49\u0e32\u0e22 \u0e1c\u0e49\u0e32\u0e44\u0e2b\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 925\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004527\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e47\u0e01\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004527 \u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e47\u0e01\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e19\u0e49\u0e33\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14 \u0e1c\u0e49\u0e32\u0e2d\u0e49\u0e2d\u0e21\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001568\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e32\u0e07\u0e1b\u0e32\u0e07\u0e0a\u0e47\u0e2d\u0e1b\u0e1e\u0e35\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001568 \u0e2b\u0e08.\u0e1b\u0e32\u0e07\u0e1b\u0e32\u0e07\u0e0a\u0e47\u0e2d\u0e1b\u0e1e\u0e35 2569-07-13 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002027\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e01\u0e23\u0e35\u0e19\u0e04\u0e23\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002027 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e01\u0e23\u0e35\u0e19\u0e04\u0e23\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0705569003162\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e4b\u0e19\u0e41\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003162 \u0e1a\u0e08.\u0e2d\u0e31\u0e4b\u0e19\u0e41\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1c\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 20\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002603\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e0a\u0e34\u0e15 \u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002603 \u0e1a\u0e08.\u0e27\u0e34\u0e0a\u0e34\u0e15 \u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 16\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007052\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007052 \u0e1a\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22-\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 97\/92  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007061\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e1e\u0e2d\u0e23\u0e4c\u0e04 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007061 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e1e\u0e2d\u0e23\u0e4c\u0e04 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e01\u0e23\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30\u0e41\u0e22\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007079\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e01\u0e30 \u0e1e\u0e32 \u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007079 \u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e01\u0e30 \u0e1e\u0e32 \u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e02\u0e19 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007303\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e1f\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007303 \u0e1a\u0e08.\u0e25\u0e34\u0e1f\u0e27\u0e48\u0e32\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 346\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007311\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e1a\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"13132\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"13132\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007311 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e1a\u0e35 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 13132 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e01\u0e23\u0e35\u0e19\u0e1c\u0e49\u0e32 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22\u0e1c\u0e49\u0e32 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e25\u0e07\u0e1a\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e1b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1c\u0e34\u0e27\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 95\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007338\",\"name_th\":\"\u0e1a\u0e08. \u0e2d\u0e34\u0e19\u0e42\u0e19 \u0e40\u0e17\u0e04 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007338 \u0e1a\u0e08. \u0e2d\u0e34\u0e19\u0e42\u0e19 \u0e40\u0e17\u0e04 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007346\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e47\u0e01 \u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007346 \u0e1a\u0e08.\u0e40\u0e25\u0e47\u0e01 \u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46900 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0775569002972\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c\u0e41\u0e2d\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e0b\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002972 \u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c\u0e41\u0e2d\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e0b\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22          \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e04\u0e48\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u4e0d\u52d5\u7523 11\/183  \u0e0b\u0e2d\u0e22 41 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002688\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002688 \u0e1a\u0e08.\u0e28\u0e34\u0e25\u0e1b\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 110\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002696\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e1e\u0e23\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c 3 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47111\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47111\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002696 \u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e1e\u0e23\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c 3 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e21\u0e34\u0e19\u0e34\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 218\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002700\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e0a.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002700 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e0a.\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e1d\u0e31\u0e07\u0e17\u0e48\u0e2d \u0e07\u0e32\u0e19\u0e17\u0e48\u0e2d \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46  \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e2d\u0e23\u0e4c \u5efa\u8a2d 98\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002718\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e01\u0e2d\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e08.\u0e17\u0e35.\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01302\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01302\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002718 \u0e1a\u0e08.\u0e21\u0e32\u0e01\u0e2d\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e08.\u0e17\u0e35.\u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 01302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e2a\u0e14 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e17\u0e30\u0e25\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 109  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0813569000454\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e0b\u0e34\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e25\u0e31\u0e2a\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0813569000454 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e0b\u0e34\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e25\u0e31\u0e2a 2569-07-13 1000000 20299 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u88fd\u9020 233  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569012900\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e08\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012900 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e08\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 98\/277  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012934\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e14\u0e49\u0e32 \u0e40\u0e21\u0e40\u0e19\u0e17\u0e40\u0e21\u0e49\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012934 \u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e14\u0e49\u0e32 \u0e40\u0e21\u0e40\u0e19\u0e17\u0e40\u0e21\u0e49\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u4e0d\u52d5\u7523 119\/79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010311\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e13\u0e11\u0e4c\u0e27\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010311 \u0e1a\u0e08.\u0e21\u0e31\u0e13\u0e11\u0e4c\u0e27\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 40\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005724\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35.\u0e27\u0e35.\u0e40\u0e2d.\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47731\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47731\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005724 \u0e1a\u0e08.\u0e1a\u0e35.\u0e27\u0e35.\u0e40\u0e2d.\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47731 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e27\u0e48\u0e19 \u0e40\u0e25\u0e19\u0e2a\u0e4c \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e04\u0e40\u0e25\u0e19\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e15\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138  \u0e16\u0e19\u0e19\u0e08\u0e38\u0e15\u0e34\u0e2d\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005732\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e27\u0e34\u0e2a\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005732 \u0e1a\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e27\u0e34\u0e2a\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e38\u0e4b\u0e22\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001036\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e31\u0e08\u0e08\u0e31\u0e07 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47991\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47991\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001036 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e31\u0e08\u0e08\u0e31\u0e07 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 1000000 47991 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e02\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e39\u0e40\u0e25\u0e35\u0e22\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0933569000313\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1e\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0933569000313 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1e\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-13 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0105569131948\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e0b\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131948 \u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e0b\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 137\/67  \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e1927 \u0e41\u0e22\u0e01 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131956\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e42\u0e19\u0e30 \u0e1a\u0e35 \u0e42\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131956 \u0e1a\u0e08.\u0e1e\u0e35 \u0e42\u0e19\u0e30 \u0e1a\u0e35 \u0e42\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2a\u0e32\u0e40\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 655  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 36 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131972\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2a\u0e0b\u0e34\u0e42\u0e2d \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131972 \u0e1a\u0e08.\u0e40\u0e17\u0e2a\u0e0b\u0e34\u0e42\u0e2d \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e40\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e40\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2823\/3  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e32\u0e22\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 312 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132031\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132031 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e1e\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 229\/151  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132049\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e42\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132049 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e42\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e15\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e14\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 427  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132057\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e17\u0e23\u0e31\u0e48\u0e25 \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132057 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e17\u0e23\u0e31\u0e48\u0e25 \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (domestic) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 102\/32  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132073\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e0b\u0e0b\u0e35\u0e48 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10503\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10503\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132073 \u0e1a\u0e08.\u0e08\u0e39\u0e0b\u0e0b\u0e35\u0e48 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 10503 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 362  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 92\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002399\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1f\u0e34\u0e01\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002399 \u0e2b\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1f\u0e34\u0e01 2569-07-12 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 57\/423  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002402\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e24\u0e01\u0e29\u0e32\u0e2d\u0e42\u0e01\u0e23\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002402 \u0e2b\u0e08.\u0e1e\u0e24\u0e01\u0e29\u0e32\u0e2d\u0e42\u0e01\u0e23 2569-07-12 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 57\/423  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002411\",\"name_th\":\"\u0e2b\u0e08. \u0e2d\u0e42\u0e01\u0e23\u0e40\u0e27\u0e25\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002411 \u0e2b\u0e08. \u0e2d\u0e42\u0e01\u0e23\u0e40\u0e27\u0e25 2569-07-12 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 57\/423  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002429\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002429 \u0e2b\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e44\u0e17\u0e22 2569-07-12 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 57\/423  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002437\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e34\u0e19\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002437 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e34\u0e19\u0e44\u0e17\u0e22 2569-07-12 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0133569002399\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (2026)\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27103\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27103\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002399 \u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (2026) 2569-07-12 1000000 27103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e2a\u0e39\u0e07 \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e15\u0e48\u0e33 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e39\u0e49\u0e1f \u88fd\u9020 5\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021492\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e07\u0e32\u0e21\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021492 \u0e1a\u0e08.\u0e14\u0e35\u0e07\u0e32\u0e21\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e35\u0e42\u0e04 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0163569000558\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000558 \u0e2b\u0e08.\u0e1a\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 2569-07-12 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e41\u0e17\u0e49 \u0e2b\u0e19\u0e31\u0e07\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036855\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e4a\u0e2d\u0e1a\u0e2e\u0e31\u0e1a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036855 \u0e1a\u0e08.\u0e08\u0e4a\u0e2d\u0e1a\u0e2e\u0e31\u0e1a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 195\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009289\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e44\u0e0a\u0e22\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009289 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e44\u0e0a\u0e22\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 342  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006679\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35(\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006679 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35(\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 41001 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u5efa\u8a2d 126\/50-51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006687\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e30\u0e42\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006687 \u0e1a\u0e08.\u0e21\u0e30\u0e42\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e0b\u0e48\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 337  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001611\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e2d\u0e2d\u0e22\u0e25\u0e4c\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001611 \u0e2b\u0e08.\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e2d\u0e2d\u0e22\u0e25\u0e4c 2569-07-12 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e2a\u0e16\u0e32\u0e19\u0e35 \u0e1b\u0e31\u0e4a\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007382\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e49\u0e01 \u0e0d\u0e32 \u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007382 \u0e2b\u0e08.\u0e40\u0e04\u0e49\u0e01 \u0e0d\u0e32 \u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c 2569-07-11 1000000 42202 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e1a\u0e1a  wifi hotspot \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e19\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e36\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21  \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e02\u0e2d\u0e07\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u5efa\u8a2d 1337\/72  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e44\u0e25\u0e1f\u0e4c\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e40\u0e2e\u0e32\u0e2a\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 233\/72 \u0e0b\u0e2d\u0e22 25 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131735\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e38\u0e02 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131735 \u0e1a\u0e08.\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e38\u0e02 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2d\u0e1a\u0e23\u0e21\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e07 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e0a\u0e48\u0e32\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e0a\u0e48\u0e32\u0e07\u0e17\u0e33\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e15\u0e32\u0e21\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 3,371,373  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131743\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e1e\u0e35 \u0e42\u0e1b\u0e23 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131743 \u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e1e\u0e35 \u0e42\u0e1b\u0e23 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/182  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e25\u0e39\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e19 \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 46 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 77 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131778\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e19\u0e2a\u0e1a\u0e32\u0e22 \u0e41\u0e2d\u0e0b\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131778 \u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e19\u0e2a\u0e1a\u0e32\u0e22 \u0e41\u0e2d\u0e0b\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e1f\u0e25\u0e15 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e07 \u4e0d\u52d5\u7523 14  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 3 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131816\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e19\u0e25\u0e35\u0e48 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131816 \u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e19\u0e25\u0e35\u0e48 \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 240\/114  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131824\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e14\u0e32\u0e23\u0e35 \u0e04\u0e25\u0e2d\u0e40\u0e0b\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131824 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e14\u0e32\u0e23\u0e35 \u0e04\u0e25\u0e2d\u0e40\u0e0b\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 741  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131832\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0a\u0e1b\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e35\u0e40\u0e25\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131832 \u0e1a\u0e08.\u0e41\u0e0a\u0e1b\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e35\u0e40\u0e25\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e0b\u0e35\u0e23\u0e35\u0e48\u0e22\u0e4c \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01 \u0e41\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e48\u0e07\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 580\/11  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 87 (\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131859\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131859 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46104 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 166\/15  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e23\u0e20\u0e35 1 \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131867\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e22\u0e2a\u0e38\u0e02\u0e25\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131867 \u0e1a\u0e08.\u0e42\u0e01\u0e22\u0e2a\u0e38\u0e02\u0e25\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32  \u0e2b\u0e21\u0e27\u0e01 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 388\/80  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e19\u0e27\u0e25\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131905\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21\u0e2a\u0e4c372 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131905 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21\u0e2a\u0e4c372 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e34\u0e14\u0e23\u0e32\u0e0a\u0e31\u0e19 39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131913\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e15\u0e23 \u0e40\u0e2e\u0e07 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131913 \u0e1a\u0e08.\u0e42\u0e04\u0e15\u0e23 \u0e40\u0e2e\u0e07 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e49\u0e32\u0e40\u0e17\u0e1b \u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e23\u0e34\u0e1a\u0e1a\u0e34\u0e49\u0e19 \u0e40\u0e0a\u0e37\u0e2d\u0e01 \u0e14\u0e49\u0e32\u0e22\u0e40\u0e22\u0e47\u0e1a\u0e1c\u0e49\u0e32 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 63 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131930\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e42\u0e23\u0e08\u0e19\u0e30\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131930 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e42\u0e23\u0e08\u0e19\u0e30\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/8  \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d25 \u0e41\u0e22\u0e012 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023070\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e1a\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023070 \u0e1a\u0e08.\u0e21\u0e39\u0e19\u0e1a\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 187\/132  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023088\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023088 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27 \u0e46 \u0e44\u0e1b \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 79\/212  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023100\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e44\u0e2e\u0e1f\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023100 \u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e44\u0e2e\u0e1f\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86\/126  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e31\u0e13\u0e11\u0e19\u0e322 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e27\u0e34\u0e19\u0e34\u0e15\u0e1a\u0e32\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e01\u0e21.7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023118\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023118 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e04\u0e38\u0e13 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e2d\u0e34\u0e2a\u0e23\u0e30 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e23\u0e39\u0e1b\u0e40\u0e25\u0e48\u0e21 \u0e44\u0e1f\u0e25\u0e4c\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e08\u0e14\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e34\u0e14\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e0a\u0e33\u0e23\u0e30\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e49\u0e38\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e17\u0e38\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111\/183  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023126\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e0b\u0e35\u0e48 \u0e42\u0e0b\u0e44\u0e0b\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023126 \u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e0b\u0e35\u0e48 \u0e42\u0e0b\u0e44\u0e0b\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 126\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023134\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e1e\u0e35\u0e40\u0e2d \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"51201\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"51201\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023134 \u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e1e\u0e35\u0e40\u0e2d \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 51201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 5\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026192\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e21 1997 \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026192 \u0e1a\u0e08.\u0e04\u0e34\u0e21 1997 \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 60\/129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026206\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e37\u0e19\u0e22\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 2008 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026206 \u0e1a\u0e08.\u0e22\u0e37\u0e19\u0e22\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 2008 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 118\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026231\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e17\u0e33\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026231 \u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e17\u0e33\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47912 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e2d\u0e31\u0e19\u0e21\u0e34\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 170\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026249\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026249 \u0e1a\u0e08.\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 58\/187  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021433\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e04\u0e2d\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021433 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e04\u0e2d\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 70209 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 78\/41 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021450\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e41\u0e0b\u0e1424 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021450 \u0e1a\u0e08.\u0e08\u0e35\u0e08\u0e35\u0e41\u0e0b\u0e1424 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (holding company) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 9\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021468\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e2d\u0e25 \u0e1a\u0e31\u0e17 \u0e1a\u0e34\u0e4a\u0e01 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021468 \u0e1a\u0e08.\u0e2a\u0e21\u0e2d\u0e25 \u0e1a\u0e31\u0e17 \u0e1a\u0e34\u0e4a\u0e01 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e21\u0e39 \u0e44\u0e01\u0e48 \u0e40\u0e1b\u0e47\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021476\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e42\u0e2d. \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021476 \u0e1a\u0e08.\u0e1e\u0e35.\u0e42\u0e2d. \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 58112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e09\u0e25\u0e32\u0e01 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e48\u0e32\u0e1a\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e4a\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 36\/223  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0195569002536\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e25\u0e14\u0e32 \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002536 \u0e1a\u0e08.\u0e40\u0e21\u0e25\u0e14\u0e32 \u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29,\u0e02\u0e27\u0e14,\u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01,\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07,\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21,\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/12  \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003009\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e1a\u0e35\u0e27\u0e35. \u0e04\u0e2d\u0e21\u0e1e\u0e23\u0e35\u0e40\u0e2e\u0e19\u0e0b\u0e35\u0e1f\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003009 \u0e2b\u0e08.\u0e2d\u0e19\u0e38\u0e01\u0e39\u0e25 \u0e1a\u0e35\u0e27\u0e35. \u0e04\u0e2d\u0e21\u0e1e\u0e23\u0e35\u0e40\u0e2e\u0e19\u0e0b\u0e35\u0e1f 2569-07-11 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (cctv) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/366  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036812\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e44\u0e2d\u0e40\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036812 \u0e1a\u0e08.\u0e40\u0e08\u0e44\u0e2d\u0e40\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e19\u0e02\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e19\u0e02\u0e31\u0e1a \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 354\/141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036821\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e31\u0e01\u0e17\u0e2d\u0e40\u0e07\u0e34\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036821 \u0e1a\u0e08.\u0e16\u0e31\u0e01\u0e17\u0e2d\u0e40\u0e07\u0e34\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 36\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009271\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e2b\u0e25\u0e07 \u0e40\u0e0b\u0e34\u0e07 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10742\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10742\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009271 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e2b\u0e25\u0e07 \u0e40\u0e0b\u0e34\u0e07 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 10742 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e49\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e40\u0e2a\u0e49\u0e19\u0e2b\u0e21\u0e35\u0e48 \u0e40\u0e2a\u0e49\u0e19\u0e1a\u0e30\u0e2b\u0e21\u0e35\u0e48 \u0e27\u0e38\u0e49\u0e19\u0e40\u0e2a\u0e49\u0e19 \u0e41\u0e1c\u0e48\u0e19\u0e40\u0e01\u0e35\u0e4a\u0e22\u0e27 \u0e41\u0e1c\u0e48\u0e19\u0e41\u0e1b\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e1b\u0e49\u0e07\u0e17\u0e38\u0e01 \u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 309  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003752\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e32\u0e27 \u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003752 \u0e1a\u0e08.\u0e41\u0e1b\u0e25\u0e07\u0e22\u0e32\u0e27 \u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u0e23\u0e16\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23 \u0e23\u0e16\u0e02\u0e38\u0e14 \u0e23\u0e16\u0e15\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e38\u0e14 \u0e44\u0e16 \u0e14\u0e31\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e02\u0e38\u0e14\u0e1a\u0e48\u0e2d \u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e14\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 186\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003761\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64922\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64922\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003761 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 64922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569001997\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e27\u0e34\u0e49\u0e19\u0e40\u0e16\u0e34\u0e07 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e08\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e21\u0e25\u0e14\u0e34\u0e49\u0e07(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28292\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28292\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001997 \u0e1a\u0e08.\u0e08\u0e27\u0e34\u0e49\u0e19\u0e40\u0e16\u0e34\u0e07 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e08\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e21\u0e25\u0e14\u0e34\u0e49\u0e07(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 28292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e08\u0e34\u0e4a\u0e01 \u0e41\u0e25\u0e30\u0e1f\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e23\u0e31\u0e1a\u0e09\u0e35\u0e14\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 888\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007226\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e0a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007226 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e0a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e28\u0e29\u0e41\u0e1b\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a\u0e43\u0e2a\u0e48\u0e41\u0e1b\u0e49\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 499\/4  \u0e0b\u0e2d\u0e22 \u0e40\u0e14\u0e0a\u0e2d\u0e38\u0e14\u0e21 14 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0345569003191\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e28\u0e23\u0e0a\u0e31\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003191 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e28\u0e23\u0e0a\u0e31\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0405569006644\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e44\u0e17\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006644 \u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e44\u0e17\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006652\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e2a\u0e37\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006652 \u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e2a\u0e37\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006661\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006661 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 243  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003572\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e23\u0e04\u0e25\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003572 \u0e1a\u0e08.\u0e42\u0e0b\u0e42\u0e23\u0e04\u0e25\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19\u0e04\u0e23\u0e35\u0e21\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000784\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e152026\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000784 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e152026 2569-07-11 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 76\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e41\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0535569000751\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e20\u0e31\u0e17\u0e23 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000751 \u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e20\u0e31\u0e17\u0e23 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0705569003146\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003146 \u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 73101 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e4d\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 258  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0743569000986\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35\u0e1e\u0e23\u0e40\u0e17\u0e27\u0e32\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000986 \u0e2b\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35\u0e1e\u0e23\u0e40\u0e17\u0e27\u0e32 2569-07-11 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 118\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007281\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e27\u0e32\u0e13\u0e30 \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007281 \u0e1a\u0e08.\u0e23\u0e32\u0e27\u0e32\u0e13\u0e30 \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c (event) \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e37\u0e48\u0e19\u0e40\u0e23\u0e34\u0e07: \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e1b \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 54\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0815569002076\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e18\u0e32\u0e23 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002076 \u0e1a\u0e08.\u0e18\u0e32\u0e18\u0e32\u0e23 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0b\u0e49\u0e07\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 195  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0815569002084\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\u0e04\u0e39\u0e13\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002084 \u0e1a\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\u0e04\u0e39\u0e13\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23\/\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569012870\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e15\u0e47\u0e21\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012870 \u0e1a\u0e08.\u0e40\u0e15\u0e47\u0e21\u0e15\u0e25\u0e2d\u0e14\u0e01\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 19\/152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012888\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e01\u0e19\u0e35\u0e48 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012888 \u0e1a\u0e08.\u0e2d\u0e34\u0e01\u0e19\u0e35\u0e48 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 173\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e27\u0e31\u0e14 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0863569000420\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\u0e44\u0e14\u0e19\u0e4c\u0e19\u0e34\u0e48\u0e07\u0e04\u0e23\u0e39\u0e0b\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"50212\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"50212\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0863569000420 \u0e2b\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\u0e44\u0e14\u0e19\u0e4c\u0e19\u0e34\u0e48\u0e07\u0e04\u0e23\u0e39\u0e0b 2569-07-11 1000000 50212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07 \u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u904b\u8f38\u30fb\u7269\u6d41 54\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0955569000579\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e21\u0e35 \u0e1f\u0e23\u0e38\u0e15 \u0e04\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000579 \u0e1a\u0e08.\u0e19\u0e32\u0e21\u0e35 \u0e1f\u0e23\u0e38\u0e15 \u0e04\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0955569000587\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000587 \u0e1a\u0e08.\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e14\u0e35\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e04\u0e14\u0e36\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e41\u0e02\u0e19\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 346  \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e42\u0e23\u0e23\u0e2a \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007340\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e0a \u0e20\u0e39\u0e1c\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007340 \u0e2b\u0e08.\u0e40\u0e14\u0e0a \u0e20\u0e39\u0e1c\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-10 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e40\u0e40\u0e17\u0e19\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e40\u0e40\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e40\u0e40\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 327\/18  \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 37 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007366\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35 \u0e2d\u0e35 \u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e04\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007366 \u0e2b\u0e08.\u0e17\u0e35 \u0e2d\u0e35 \u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e04 2569-07-10 1000000 18119 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e32\u0e07\u0e17\u0e33\u0e15\u0e23\u0e32\u0e22\u0e32\u0e07 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0b\u0e34\u0e25\u0e04\u0e4c\u0e2a\u0e01\u0e23\u0e35\u0e19 \u88fd\u9020 16  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 128\/1 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130852\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1f\u0e48\u0e32 \u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130852 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1f\u0e48\u0e32 \u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e14\u0e22\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u533b\u7642\u30fb\u798f\u7949 77\/144  \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130895\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e25\u0e15\u0e35\u0e49 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130895 \u0e1a\u0e08.\u0e21\u0e31\u0e25\u0e15\u0e35\u0e49 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34  \u0e16\u0e19\u0e19\u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130909\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e14\u0e49\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130909 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e40\u0e14\u0e49\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e07\u0e32\u0e19\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e23\u0e32\u0e04\u0e32 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 206\/183  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130925\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130925 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 88\/22  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e25\u0e39\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e19 \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 46 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 77 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130933\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e49\u0e32\u0e41\u0e21\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130933 \u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e49\u0e32\u0e41\u0e21\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/33  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 19 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130941\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e42\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130941 \u0e1a\u0e08.\u0e0b\u0e35\u0e42\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 62023 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 375\/4  \u0e16\u0e19\u0e19\u0e09\u0e25\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130968\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e01\u0e31\u0e25 \u0e23\u0e35\u0e17\u0e23\u0e35\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130968 \u0e1a\u0e08.\u0e23\u0e35\u0e01\u0e31\u0e25 \u0e23\u0e35\u0e17\u0e23\u0e35\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 78\/4  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 21 (\u0e19\u0e27\u0e28\u0e23\u0e35) \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130976\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e25\u0e32\u0e2a \u0e04\u0e34\u0e0a\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130976 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e25\u0e32\u0e2a \u0e04\u0e34\u0e0a\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 25\/3  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1716 ( \u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131034\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e0b\u0e31\u0e19\u0e2a\u0e4c \u0e17\u0e39 \u0e23\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131034 \u0e1a\u0e08.\u0e23\u0e35\u0e0b\u0e31\u0e19\u0e2a\u0e4c \u0e17\u0e39 \u0e23\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e38\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e01\u0e15\u0e23\u0e30\u0e01\u0e23\u0e49\u0e32 affiliate) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 789\/12  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e04\u0e40\u0e15\u0e49 \u0e40\u0e21\u0e0b\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131042\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e42\u0e19 \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131042 \u0e1a\u0e08.\u0e19\u0e32\u0e42\u0e19 \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46900 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 459\/33  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e30\u0e0a\u0e34 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 54 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131051\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131051 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e22\u0e37\u0e14 \u0e40\u0e17\u0e1b\u0e01\u0e32\u0e27 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e16\u0e38\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e0b\u0e2d\u0e07 \u0e09\u0e25\u0e32\u0e01 \u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 198  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 1 \u0e0b\u0e2d\u0e22 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131069\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e35\u0e48\u0e21\u0e39 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47911\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47911\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131069 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e35\u0e48\u0e21\u0e39 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47911 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e47\u0e2d\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1c\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 224\/53  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e04 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131077\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d \u0e41\u0e2d\u0e25 \u0e27\u0e32\u0e22 \u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131077 \u0e1a\u0e08.\u0e42\u0e2d \u0e41\u0e2d\u0e25 \u0e27\u0e32\u0e22 \u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e19\u0e39\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e0a\u0e49\u0e32 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e41\u0e0b\u0e19\u0e27\u0e34\u0e0a \u0e44\u0e2a\u0e49\u0e01\u0e23\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e02\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a \u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u88fd\u9020 72  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131085\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e34\u0e1e\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131085 \u0e1a\u0e08.\u0e1b\u0e34\u0e1e\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01 \u0e2d\u0e1a \u0e23\u0e35\u0e14 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e43\u0e49\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e2a\u0e1b\u0e32 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 604\/8  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131107\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131107 \u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 300\/101  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2735\/1 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131174\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e27\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131174 \u0e1a\u0e08.\u0e17\u0e35\u0e27\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 51\/75  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e1566(\u0e2a\u0e22\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131182\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131182 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e30\u0e21\u0e34\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 199\/25  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e34\u0e15\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e22\u0e01 10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131221\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e08\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131221 \u0e1a\u0e08.\u0e1e\u0e35\u0e08\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u60c5\u5831\u901a\u4fe1\u30fbit 502  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e01\u0e29\u0e23 \u0e2d\u0e31\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 8a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131255\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e17\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131255 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e17\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46900 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e0b\u0e2d\u0e22 \u0e09\u0e34\u0e21\u0e1e\u0e25\u0e35 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131263\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e22\u0e39 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131263 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e22\u0e39 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e02\u0e19 \u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e2a\u0e38\u0e19\u0e31\u0e02 \u0e41\u0e21\u0e27  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e38\u0e19\u0e31\u0e02\u0e41\u0e25\u0e30\u0e41\u0e21\u0e27\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 299\/528  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e31\u0e13\u0e11\u0e19\u0e32 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131271\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e40\u0e2d\u0e2a.\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131271 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35\u0e40\u0e2d\u0e2a.\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 11043 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u88fd\u9020 540  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e04\u0e34\u0e27\u0e23\u0e35\u0e48  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 540 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131298\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e35\u0e22 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131298 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e35\u0e22 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 (data processor) \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data center) \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 13\/6  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 64\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131301\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e0b\u0e35. \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131301 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e0b\u0e35. \u0e1e\u0e25\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5efa\u8a2d 69\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1c\u0e14\u0e38\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131310\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e19\u0e27\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131310 \u0e1a\u0e08.\u0e40\u0e25\u0e19\u0e27\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1b\u0e48\u0e32\u0e25\u0e21 \u0e1e\u0e31\u0e21\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e1b\u0e48\u0e32\u0e25\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e01\u0e4a\u0e32\u0e0b \u0e41\u0e25\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e2d\u0e19\u0e49\u0e33\u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e1c\u0e19\u0e31\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e15\u0e32\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e19\u0e49\u0e33\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e42\u0e25\u0e2b\u0e30\u0e41\u0e25\u0e30\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131336\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e35\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e40\u0e23\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131336 \u0e1a\u0e08.\u0e25\u0e35\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e40\u0e23\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e39\u0e48\u0e04\u0e13\u0e30\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 97\/284  \u0e0b\u0e2d\u0e22 \u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e41\u0e01\u0e49\u0e27 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131352\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131352 \u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e42\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 4  \u0e0b\u0e2d\u0e22 \u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\u0e23\u0e32\u0e0a\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131379\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e01\u0e32\u0e23\u0e35\u0e21\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131379 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e01\u0e32\u0e23\u0e35\u0e21\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e06\u0e29\u0e13\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2e\u0e31\u0e08\u0e22\u0e4c \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 22\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131387\",\"name_th\":\"\u0e1a\u0e08.\u0e18.\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e08\u0e08\u0e32\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131387 \u0e1a\u0e08.\u0e18.\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e34\u0e08\u0e08\u0e32\u0e01\u0e38\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e25\u0e33\u0e42\u0e1e\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 170\/31  \u0e16\u0e19\u0e19\u0e2a\u0e30\u0e41\u0e01\u0e07\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131395\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e35\u0e49\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131395 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e35\u0e49\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e1a\u0e1a\u0e25\u0e34\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e31\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 139  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e25\u0e39\u0e0a\u0e34\u0e1e\u0e2a\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s-603 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e48\u0e2d 10) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131409\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e0b\u0e35\u0e48 \u0e21\u0e32\u0e22\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131409 \u0e1a\u0e08.\u0e0b\u0e39\u0e0b\u0e35\u0e48 \u0e21\u0e32\u0e22\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e08\u0e34\u0e15\u0e40\u0e27\u0e0a \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07 \u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 55\/54  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131425\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85423\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85423\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131425 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 85423 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e33 workshop diy \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c,\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d,\u0e07\u0e32\u0e19\u0e1c\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u6559\u80b2 1768  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131433\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e22\u0e32\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e213 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131433 \u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e22\u0e32\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e213 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e02\u0e32\u0e22\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/1  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 109 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131441\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e33\u0e1e\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131441 \u0e1a\u0e08.\u0e19\u0e33\u0e1e\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e04\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 18\/194  \u0e16\u0e19\u0e19\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131468\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e08\u0e19\u0e15\u0e32\u0e23\u0e4c  \u0e40\u0e2d\u0e19\u0e40\u0e17\u0e2d\u0e44\u0e1e\u0e23\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131468 \u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e08\u0e19\u0e15\u0e32\u0e23\u0e4c  \u0e40\u0e2d\u0e19\u0e40\u0e17\u0e2d\u0e44\u0e1e\u0e23\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e49 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e15\u0e4a\u0e30 \u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u88fd\u9020 39\/125  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e23\u0e30\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131476\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01 \u0e17\u0e39\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47895\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47895\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131476 \u0e1a\u0e08.\u0e42\u0e01 \u0e17\u0e39\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47895 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/14  \u0e16\u0e19\u0e1901 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131484\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e42\u0e1a\u0e1f \u0e40\u0e2d\u0e25\u0e42\u0e27\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131484 \u0e1a\u0e08.\u0e2d\u0e30\u0e42\u0e1a\u0e1f \u0e40\u0e2d\u0e25\u0e42\u0e27\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47912 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131492\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e34\u0e21-\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131492 \u0e1a\u0e08.\u0e40\u0e14\u0e34\u0e21-\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e41\u0e02\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 51  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131506\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e01\u0e49\u0e32 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131506 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e01\u0e49\u0e32 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u88fd\u9020 99\/256  \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131514\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131514 \u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 34\/23  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131522\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131522 \u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 34\/23  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131531\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e0b\u0e31\u0e19\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131531 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e0b\u0e31\u0e19\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e38\u0e01\u0e40\u0e1a\u0e34\u0e01 \u0e25\u0e07\u0e17\u0e38\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e23\u0e39\u0e1f\u0e17\u0e47\u0e2d\u0e1b \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e41\u0e1a\u0e1a\u0e25\u0e2d\u0e22\u0e19\u0e49\u0e33 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e1b\u0e31\u0e49\u0e21\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 206\/183  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e21\u0e17\u0e42\u0e17\u0e23 \u0e2a\u0e32\u0e17\u0e23 \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131557\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35 \u0e40\u0e19\u0e47\u0e17\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131557 \u0e1a\u0e08.\u0e14\u0e35 \u0e40\u0e19\u0e47\u0e17\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 49323 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 agency \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 48\/33  \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131573\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e2d\u0e19\u0e32\u0e25\u0e34\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131573 \u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e2d\u0e19\u0e32\u0e25\u0e34\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/23  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131581\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e27\u0e4c\u0e27\u0e48\u0e32 \u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131581 \u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e27\u0e4c\u0e27\u0e48\u0e32 \u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e21\u0e19\u0e18\u0e32\u0e15\u0e38\u0e2f \u0e41\u0e22\u0e01 35-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131590\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131590 \u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/23  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131611\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e0b\u0e34\u0e19\u0e18\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131611 \u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e0b\u0e34\u0e19\u0e18\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 18\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e33\u0e23\u0e32\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131620\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e0b\u0e14 \u0e44\u0e17\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131620 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c\u0e41\u0e0b\u0e14 \u0e44\u0e17\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 64202 \u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 11\/118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131654\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23 \u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131654 \u0e1a\u0e08.\u0e40\u0e01\u0e23 \u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47912 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131662\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e14\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131662 \u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e14\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 186  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 14 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131671\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23 \u0e41\u0e2b\u0e27\u0e19 \u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131671 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23 \u0e41\u0e2b\u0e27\u0e19 \u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21\u0e08\u0e35\u0e19 \u0e01\u0e4b\u0e27\u0e22\u0e08\u0e31\u0e4a\u0e1a\u0e0d\u0e27\u0e19 \u0e1c\u0e31\u0e14\u0e44\u0e17 \u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01 \u0e41\u0e08\u0e48\u0e27\u0e1a\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01\u0e41\u0e08\u0e48\u0e27\u0e1b\u0e25\u0e32\u0e23\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e1f\u0e2a\u0e1a\u0e38\u0e4a\u0e04 \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 422\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 50 \u0e41\u0e22\u0e01 11-13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131689\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e25\u0e04\u0e2d\u0e19 \u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131689 \u0e1a\u0e08.\u0e1f\u0e2d\u0e25\u0e04\u0e2d\u0e19 \u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d - \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 - \u0e1b\u0e25\u0e35\u0e01 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30 \u0e40\u0e01\u0e48\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/4  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 6\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131701\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e14\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131701 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e14\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 282  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131719\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131719 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 338\/86  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e21.\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e40\u0e1e\u0e25\u0e2a \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 81-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002364\",\"name_th\":\"\u0e2b\u0e08. \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e14\u0e35\u0e14\u0e35\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002364 \u0e2b\u0e08. \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e14\u0e35\u0e14\u0e35 2569-07-10 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 8\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002372\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e1e\u0e25\u0e31\u0e2a\u0e2d\u0e42\u0e01\u0e23\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002372 \u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e1e\u0e25\u0e31\u0e2a\u0e2d\u0e42\u0e01\u0e23 2569-07-10 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 8\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022987\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022987 \u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 (\u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21) \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 222\/57  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0b\u0e19\u0e42\u0e17\u0e23 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023002\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e40\u0e27\u0e35\u0e22 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023002 \u0e1a\u0e08.\u0e0b\u0e32\u0e40\u0e27\u0e35\u0e22 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e44\u0e2d\u0e17\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 62\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023011\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01 \u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023011 \u0e1a\u0e08.\u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01 \u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (control system) \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u88fd\u9020 98\/55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023061\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e1e\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023061 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e1e\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u5efa\u8a2d 583  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002143\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e19  \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e04\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002143 \u0e2b\u0e08.\u0e40\u0e04 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e19  \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e04\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-10 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 56\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026061\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e04\u0e32\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026061 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e04\u0e32\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e15\u0e34\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e01\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026087\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e21\u0e34-\u0e40\u0e21\u0e14\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026087 \u0e1a\u0e08.\u0e40\u0e0b\u0e21\u0e34-\u0e40\u0e21\u0e14\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e01 \u0e2a\u0e01\u0e23\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 9\/138  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026141\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e2b\u0e32\u0e22\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026141 \u0e1a\u0e08.\u0e2a\u0e2b\u0e32\u0e22\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 29\/555  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026150\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e15\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026150 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e15\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e15\u0e23\u0e4c \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e42\u0e17\u0e23\u0e19\u0e34\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u88fd\u9020 11\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026168\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e15\u0e34\u0e18\u0e23\u0e23\u0e2145 \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026168 \u0e1a\u0e08.\u0e40\u0e19\u0e15\u0e34\u0e18\u0e23\u0e23\u0e2145 \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 69100 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 18\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021361\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e32\u0e25\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021361 \u0e1a\u0e08.\u0e1b\u0e32\u0e25\u0e42\u0e23\u0e08\u0e19\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 33\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021379\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e34\u0e2a\u0e22\u0e32 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93292\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93292\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021379 \u0e1a\u0e08.\u0e2d\u0e23\u0e34\u0e2a\u0e22\u0e32 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 93292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 community \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 11\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e02\u0e31\u0e19\u0e40\u0e07\u0e34\u0e19 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021409\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e39\u0e17\u0e23\u0e49\u0e32\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021409 \u0e1a\u0e08.\u0e19\u0e39\u0e17\u0e23\u0e49\u0e32\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61\/523  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021417\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e14 \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021417 \u0e1a\u0e08.\u0e40\u0e21\u0e14 \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e22\u0e32\u0e07 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e1c\u0e49\u0e32 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1d\u0e38\u0e48\u0e19 \u0e2b\u0e19\u0e49\u0e32\u0e01\u0e32\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14(ppe) \u0e2b\u0e21\u0e27\u0e01\u0e04\u0e25\u0e38\u0e21\u0e1c\u0e21 \u0e0a\u0e38\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e40\u0e08\u0e25\u0e25\u0e49\u0e32\u0e07\u0e21\u0e37\u0e2d \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e42\u0e23\u0e04 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0143569001163\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e18\u0e19\u0e32\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001163 \u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e18\u0e19\u0e32\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c 2569-07-10 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004539\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004539 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004547\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e01\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"'13210\",\"province_ja\":\"\",\"search_text\":\"0145569004547 \u0e1a\u0e08.\u0e0b\u0e31\u0e01\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e2d\u0e1a\u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e35\u0e14\u0e1c\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e1a\u0e1c\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e1c\u0e07\u0e0b\u0e31\u0e01\u0e1f\u0e2d\u0e01 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e1c\u0e49\u0e32\u0e19\u0e38\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46\\\",10\/07\/2569\\\" \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 \u0e15.\u0e04\u0e32\u0e19\u0e2b\u0e32\u0e21 '13210 \"},{\"reg_no\":\"0145569004555\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004555 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e47\u0e2d\u0e1b \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e20\u0e32\u0e27\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004563\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004563 \u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 23922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 \u0e2b\u0e34\u0e19\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004571\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004571 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e40\u0e0a\u0e48\u0e19 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e15\u0e39\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e23\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 803\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0163569000540\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e34\u0e19\u0e35 \u0e2a\u0e44\u0e15\u0e25\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000540 \u0e2b\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e2a\u0e34\u0e19\u0e35 \u0e2a\u0e44\u0e15\u0e25\u0e4c 2569-07-10 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e38\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e2a\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15\/4  \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e14\u0e32 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001581\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e44\u0e21\u0e19\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28240\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28240\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001581 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e44\u0e21\u0e19\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 28240 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e23\u0e07\u0e42\u0e21\u0e48\u0e2b\u0e34\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 79\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001599\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e1f \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001599 \u0e1a\u0e08.\u0e40\u0e0a\u0e1f \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e23\u0e39\u0e1f\u0e17\u0e47\u0e2d\u0e1b (solar rooftop) \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e21 (solar farm) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19  (energy storage system) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e15\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 1\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002510\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e17\u0e41\u0e27\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002510 \u0e1a\u0e08.\u0e41\u0e04\u0e17\u0e41\u0e27\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 501\/1  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002528\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002528 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07 \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1c\u0e07\u0e27\u0e07\u0e08\u0e23\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e25\u0e2d\u0e14\u0e44\u0e1f \u0e40\u0e2a\u0e32\u0e44\u0e1f \u0e42\u0e04\u0e21\u0e44\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e21\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 78\/21  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002975\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35.\u0e42\u0e2d.\u0e1e\u0e35.\u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002975 \u0e2b\u0e08.\u0e1e\u0e35.\u0e42\u0e2d.\u0e1e\u0e35.\u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 2569-07-10 1000000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 262\/5  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e23\u0e35\u0e1e\u0e39\u0e19\u0e2a\u0e38\u0e021 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002983\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002983 \u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-10 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 116\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036545\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e07\u0e32\u0e21\u0e22\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036545 \u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e07\u0e32\u0e21\u0e22\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 1\/116  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036561\",\"name_th\":\"\u0e1a\u0e08.\u0e2d.\u0e41\u0e2a\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036561 \u0e1a\u0e08.\u0e2d.\u0e41\u0e2a\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 388\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036588\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e2a\u0e01\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036588 \u0e1a\u0e08.\u0e1e\u0e32\u0e2a\u0e01\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 444\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036618\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32\u0e19\u0e48\u0e32 \u0e2a\u0e27\u0e35\u0e17\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036618 \u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32\u0e19\u0e48\u0e32 \u0e2a\u0e27\u0e35\u0e17\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u88fd\u9020 159\/119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036642\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35 \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036642 \u0e1a\u0e08.\u0e0b\u0e35 \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036677\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e42\u0e14 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036677 \u0e1a\u0e08.\u0e41\u0e21\u0e19\u0e42\u0e14 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e40\u0e14\u0e47\u0e01\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u6559\u80b2 178\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036791\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e2d\u0e14\u0e17\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036791 \u0e1a\u0e08.\u0e22\u0e2d\u0e14\u0e17\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 118\/427  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036804\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e19\u0e48\u0e32 \u0e2d\u0e34\u0e19\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47896\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47896\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036804 \u0e1a\u0e08.\u0e25\u0e39\u0e19\u0e48\u0e32 \u0e2d\u0e34\u0e19\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47896 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76\/134  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009211\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e44\u0e15\u0e23\u0e15\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009211 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e44\u0e15\u0e23\u0e15\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e32\u0e40\u0e25\u0e17\u0e44\u0e21\u0e49 \u0e25\u0e31\u0e07\u0e44\u0e21\u0e49 \u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 333\/60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009238\",\"name_th\":\"\u0e1a\u0e08. \u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e34\u0e15\u0e22\u0e1e\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009238 \u0e1a\u0e08. \u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e34\u0e15\u0e22\u0e1e\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 25\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009254\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0a\u0e22\u0e1b\u0e23\u0e32\u0e0a\u0e0d\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009254 \u0e1a\u0e08.\u0e44\u0e0a\u0e22\u0e1b\u0e23\u0e32\u0e0a\u0e0d\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 305,305\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003710\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003710 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e04\u0e27\u0e2d\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e08\u0e31\u0e14\u0e40\u0e23\u0e35\u0e22\u0e07 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d \u0e41\u0e1e\u0e47\u0e04\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 69\/84  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e23\u0e35\u0e40\u0e17\u0e1e\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 8 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0265569000800\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e1f\u0e23\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000800 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e1f\u0e23\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2d\u0e2d\u0e01\u0e02\u0e2d\u0e07  \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23  \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u904b\u8f38\u30fb\u7269\u6d41 535  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0305569007196\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e0b\u0e32 \u0e42\u0e08\u0e2d\u0e34\u0e2d\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007196 \u0e1a\u0e08.\u0e04\u0e32\u0e0b\u0e32 \u0e42\u0e08\u0e2d\u0e34\u0e2d\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e49\u0e32\u0e27\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e32\u0e2b\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 461  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007218\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e1f \u0e2d\u0e31\u0e1e \u0e04\u0e32\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007218 \u0e1a\u0e08.\u0e21\u0e39\u0e1f \u0e2d\u0e31\u0e1e \u0e04\u0e32\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e02\u0e31\u0e1a\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e42\u0e14\u0e22\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 941  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001030\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001030 \u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c 2569-07-10 1000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u5efa\u8a2d 240  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569001872\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001872 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 42   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 101 \u0e16\u0e19\u0e19\u0e2d\u0e34\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0325569001210\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001210 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e21\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e0a\u0e48\u0e32 \u0e0a\u0e48\u0e27\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e1b\u0e35 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u4e0d\u52d5\u7523 279  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0333569000653\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0333569000653 \u0e2b\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-10 1000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e04\u0e48\u0e32\u0e41\u0e23\u0e07\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e25\u0e2b\u0e30 \u0e01\u0e25\u0e36\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e01\u0e31\u0e19\u0e2a\u0e32\u0e14 \u0e42\u0e04\u0e23\u0e07\u0e23\u0e31\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e40\u0e2b\u0e25\u0e47\u0e01  \u0e07\u0e32\u0e19\u0e17\u0e48\u0e2d \u0e17\u0e48\u0e2d\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19 \u0e16\u0e31\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1d\u0e49\u0e32\u0e40\u0e1e\u0e14\u0e32\u0e19 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u88fd\u9020 198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0343569001871\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e04\u0e27\u0e31\u0e15\u0e23 789\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001871 \u0e2b\u0e08.\u0e19\u0e32\u0e04\u0e27\u0e31\u0e15\u0e23 789 2569-07-10 1000000 47739 ) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d-\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e42\u0e25\u0e2b\u0e30\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e25\u0e31\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47\u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0343569001889\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21 678\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001889 \u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21 678 2569-07-10 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e16\u0e19\u0e19 \u0e44\u0e1f\u0e2a\u0e48\u0e2d\u0e07\u0e16\u0e19\u0e19 \u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u5efa\u8a2d 70  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003182\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e1e\u0e35.\u0e1e\u0e35. (2009) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10795\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10795\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003182 \u0e1a\u0e08.\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e1e\u0e35.\u0e1e\u0e35. (2009) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 10795 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u88fd\u9020 138  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e2d\u0e19\u0e0a\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0403569003066\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 1963\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003066 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 1963 2569-07-10 1000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006598\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d.\u0e40\u0e2d\u0e47\u0e19. \u0e1e\u0e25\u0e31\u0e2a \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006598 \u0e1a\u0e08.\u0e44\u0e2d.\u0e40\u0e2d\u0e47\u0e19. \u0e1e\u0e25\u0e31\u0e2a \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 725\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006628\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e04\u0e38\u0e13\u0e21\u0e35\u0e41\u0e1f\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006628 \u0e1a\u0e08.\u0e21\u0e35\u0e04\u0e38\u0e13\u0e21\u0e35\u0e41\u0e1f\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 194  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006636\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e2d\u0e1f \u0e23\u0e35\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006636 \u0e1a\u0e08.\u0e17\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e40\u0e2d\u0e1f \u0e23\u0e35\u0e0b\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 822\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003556\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003556 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49 \u0e41\u0e01\u0e48\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e02\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01. \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02. \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e04. \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e07. \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08. \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e09. \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e0a. \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e0b. \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 595\/5  \u0e16\u0e19\u0e19\u0e17\u0e2b\u0e32\u0e23 (\u0e2b\u0e19\u0e2d\u0e07\u0e02\u0e2d\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07) \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003564\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e0b\u0e0b\u0e35\u0e22\u0e4c \u0e40\u0e17\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003564 \u0e1a\u0e08.\u0e1f\u0e34\u0e0b\u0e0b\u0e35\u0e22\u0e4c \u0e40\u0e17\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 200\/229  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0433569000415\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1e\u0e37\u0e0a\u0e1c\u0e25 2569\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000415 \u0e2b\u0e08.\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e1e\u0e37\u0e0a\u0e1c\u0e25 2569 2569-07-10 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 275  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0445569001693\",\"name_th\":\"\u0e1a\u0e08.55 \u0e14\u0e35 \u0e40\u0e21\u0e17\u0e31\u0e25 (\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001693 \u0e1a\u0e08.55 \u0e14\u0e35 \u0e40\u0e21\u0e17\u0e31\u0e25 (\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22 \u0e41\u0e1c\u0e48\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e35\u0e14\u0e25\u0e2d\u0e19 (\u0e40\u0e21\u0e17\u0e31\u0e25\u0e0a\u0e35\u0e17) \u0e41\u0e1c\u0e48\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e1c\u0e48\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e0b\u0e34\u0e07\u0e04\u0e4c \u0e41\u0e1c\u0e48\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e41\u0e1c\u0e07\u0e01\u0e31\u0e19\u0e2a\u0e32\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e22\u0e36\u0e14\u0e40\u0e08\u0e32\u0e30 \u0e2a\u0e01\u0e23\u0e39 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e19\u0e31\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0463569000709\",\"name_th\":\"\u0e2b\u0e08.\u0e1b.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 168\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000709 \u0e2b\u0e08.\u0e1b.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 168 2569-07-10 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0463569000725\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e34\u0e40\u0e19\u0e15\u0e23\u0e2d\u0e2d\u0e14\u0e34\u0e42\u0e2d  \u0e0b\u0e32\u0e27\u0e14\u0e4c\u0e40\u0e17\u0e04\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000725 \u0e2b\u0e08.\u0e1e\u0e34\u0e40\u0e19\u0e15\u0e23\u0e2d\u0e2d\u0e14\u0e34\u0e42\u0e2d  \u0e0b\u0e32\u0e27\u0e14\u0e4c\u0e40\u0e17\u0e04 2569-07-10 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0503569004606\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e2d\u0e40\u0e2b\u0e21\u0e32\u0e30\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004606 \u0e2b\u0e08.\u0e1e\u0e2d\u0e40\u0e2b\u0e21\u0e32\u0e30 2569-07-10 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43  \u0e0b\u0e2d\u0e22 \u0e1b\u0e48\u0e32\u0e2b\u0e49\u0e32 \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004614\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e37\u0e2d\u0e2a\u0e32\u0e23\u0e1e\u0e31\u0e14\u0e0a\u0e48\u0e32\u0e07\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004614 \u0e2b\u0e08.\u0e21\u0e37\u0e2d\u0e2a\u0e32\u0e23\u0e1e\u0e31\u0e14\u0e0a\u0e48\u0e32\u0e07 2569-07-10 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004622\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24109\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24109\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004622 \u0e2b\u0e08.\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 2569-07-10 1000000 24109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e23\u0e35\u0e14\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e48\u0e2d\u0e2b\u0e25\u0e2d\u0e21\u0e42\u0e25\u0e2b\u0e30 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004631\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1f\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e25\u0e32\u0e01\u0e23\u0e39\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004631 \u0e2b\u0e08.\u0e40\u0e1f\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e25\u0e32\u0e01\u0e23\u0e39 2569-07-10 1000000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004649\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e44\u0e21\u0e19\u0e4c\u0e17\u0e23\u0e31\u0e04\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46631\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46631\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004649 \u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e44\u0e21\u0e19\u0e4c\u0e17\u0e23\u0e31\u0e04 2569-07-10 1000000 46631 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e38\u0e14 \u0e02\u0e19 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 136  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004657\",\"name_th\":\"\u0e2b\u0e08.\u0e43\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e38\u0e02\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004657 \u0e2b\u0e08.\u0e43\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e38\u0e02 2569-07-10 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43  \u0e0b\u0e2d\u0e22 \u0e1b\u0e48\u0e32\u0e2b\u0e49\u0e32 \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004665\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e39\u0e40\u0e25\u0e2d\u0e27\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e27\u0e22\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004665 \u0e2b\u0e08.\u0e1a\u0e39\u0e40\u0e25\u0e2d\u0e27\u0e32\u0e23\u0e4c\u0e14\u0e40\u0e27\u0e22\u0e4c 2569-07-10 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 15\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004673\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d-\u0e27\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004673 \u0e2b\u0e08.\u0e40\u0e2d-\u0e27\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 2569-07-10 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23   \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2b\u0e21\u0e49\u0e2d\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 180\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004681\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e40\u0e15\u0e22\u0e4c\u0e42\u0e2e\u0e21\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004681 \u0e2b\u0e08.\u0e2a\u0e40\u0e15\u0e22\u0e4c\u0e42\u0e2e\u0e21 2569-07-10 1000000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43  \u0e0b\u0e2d\u0e22 \u0e1b\u0e48\u0e32\u0e2b\u0e49\u0e32 \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004690\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e31\u0e19\u0e15\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004690 \u0e2b\u0e08.\u0e2a\u0e31\u0e19\u0e15\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 15\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004703\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e23\u0e49\u0e14\u0e40\u0e25\u0e19\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004703 \u0e2b\u0e08.\u0e42\u0e23\u0e49\u0e14\u0e40\u0e25\u0e19 2569-07-10 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 15\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004711\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e0b\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e19 \u0e40\u0e0b\u0e47\u0e15\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004711 \u0e2b\u0e08.\u0e41\u0e0b\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e19 \u0e40\u0e0b\u0e47\u0e15 2569-07-10 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015618\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35.\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015618 \u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e2a.\u0e1e\u0e35.\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015626\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015626 \u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e32\u0e2a\u0e19\u0e2a\u0e16\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 454  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015634\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015634 \u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e22\u0e39\u0e40\u0e19\u0e35\u0e48\u0e22\u0e19 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 - \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 - \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 224\/84  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015642\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e07\u0e27\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015642 \u0e1a\u0e08.\u0e2a\u0e07\u0e27\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47525 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 375  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015651\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e42\u0e1f\u0e23\u0e40\u0e17\u0e04 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015651 \u0e1a\u0e08.\u0e40\u0e19\u0e42\u0e1f\u0e23\u0e40\u0e17\u0e04 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46441 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015669\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e40\u0e27\u0e25\u0e40\u0e25\u0e48 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015669 \u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e40\u0e27\u0e25\u0e40\u0e25\u0e48 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e4d\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e0b\u0e36\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e32\u0e23\u0e01\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e47\u0e01 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 131\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015685\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e44\u0e2b\u0e21\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015685 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e44\u0e2b\u0e21\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e2d\u0e07\u0e1d\u0e32\u0e01 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e41\u0e2e\u0e19\u0e14\u0e4c\u0e40\u0e21\u0e14 \u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015693\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015693 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e15\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 51   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 804 \u0e16\u0e19\u0e19\u0e28\u0e34\u0e23\u0e34\u0e21\u0e31\u0e07\u0e04\u0e25\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015707\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e40\u0e21\u0e2a  \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e01\u0e4b\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01272\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01272\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015707 \u0e1a\u0e08.\u0e2d\u0e40\u0e21\u0e2a  \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e01\u0e4b\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 01272 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e25\u0e39\u0e01\u0e01\u0e32\u0e41\u0e1f \u0e02\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e02\u0e32\u0e22\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e1b\u0e25\u0e39\u0e01\u0e1e\u0e37\u0e0a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e46 \u8fb2\u6797\u6c34\u7523 117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015715\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1a\u0e35\u0e19\u0e35\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015715 \u0e1a\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e1a\u0e35\u0e19\u0e35\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e01\u0e33\u0e08\u0e31\u0e14\u0e1d\u0e38\u0e48\u0e19 \u0e02\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19 \u0e25\u0e49\u0e32\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e07\u0e32\u0e19 \u0e17\u0e33 \u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 239  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001404\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e35\u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33131\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33131\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001404 \u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e35\u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 33131 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 274  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001381\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b (1988)\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001381 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b (1988) 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 116\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001399\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001399 \u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 2569-07-10 1000000 72102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e1e\u0e37\u0e0a \u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 (\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e44\u0e1c\u0e48\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e46) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 36\/32  \u0e0b\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e01\u0e48\u0e32 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001402\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e1b\u0e23\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001402 \u0e2b\u0e08.\u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e1b\u0e23 2569-07-10 1000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u6559\u80b2 44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001411\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e1e\u0e42\u0e0a\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001411 \u0e2b\u0e08.\u0e19\u0e1e\u0e42\u0e0a\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 2569-07-10 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0555569000581\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e08\u0e35 \u0e2b\u0e21\u0e39\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000581 \u0e1a\u0e08.\u0e1e\u0e35\u0e08\u0e35 \u0e2b\u0e21\u0e39\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0565569000599\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e42\u0e14\u0e23\u0e34 \u0e2d\u0e30\u0e01\u0e23\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01279\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01279\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000599 \u0e1a\u0e08.\u0e21\u0e34\u0e42\u0e14\u0e23\u0e34 \u0e2d\u0e30\u0e01\u0e23\u0e34\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 01279 \u0e1c\u0e25\u0e34\u0e15 \/ \u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \/ \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e43\u0e1a\u0e2b\u0e21\u0e48\u0e2d\u0e19 \u0e1c\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u8fb2\u6797\u6c34\u7523 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0565569000602\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e19\u0e38\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000602 \u0e1a\u0e08.\u0e20\u0e32\u0e19\u0e38\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 190  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0565569000611\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e18\u0e32\u0e23\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000611 \u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e18\u0e32\u0e23\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 159  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0575569004454\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22  456 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004454 \u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22  456 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 363  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001541\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e35\u0e40\u0e0b\u0e34\u0e1f\u0e2d\u0e34\u0e19\u0e19\u0e35\u0e15\u0e35\u0e49\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001541 \u0e2b\u0e08.\u0e23\u0e35\u0e40\u0e0b\u0e34\u0e1f\u0e2d\u0e34\u0e19\u0e19\u0e35\u0e15\u0e35\u0e49 2569-07-10 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001550\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e04 \u0e44\u0e01\u0e48\u0e2a\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001550 \u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e04 \u0e44\u0e01\u0e48\u0e2a\u0e14 2569-07-10 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e44\u0e01\u0e48\u0e2a\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569001985\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e14\u0e0a\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01500\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01500\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001985 \u0e1a\u0e08.\u0e42\u0e14\u0e0a\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 01500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u8fb2\u6797\u6c34\u7523 31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0615569000563\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e0b\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000563 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e0b\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 (mep) \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a epc, epcm, design & build  \u0e41\u0e25\u0e30 turnkey project \u5efa\u8a2d 77\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0623569000715\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e0a\u0e39\u0e2a\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000715 \u0e2b\u0e08.\u0e41\u0e2d\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e0a\u0e39\u0e2a\u0e4c 2569-07-10 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e0b\u0e2d\u0e22 3 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0633569000693\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e22\u0e32 \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e31\u0e25\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000693 \u0e2b\u0e08.\u0e21\u0e22\u0e32 \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e31\u0e25 2569-07-10 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e1a\u0e1a\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e1a\u0e1a\u0e2b\u0e25\u0e48\u0e2d\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 95\/19  \u0e16\u0e19\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e23\u0e23\u0e1e\u0e32\u0e01\u0e32\u0e23 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0633569000707\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e0b\u0e35 \u0e01\u0e24\u0e29\u0e13\u0e32\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000707 \u0e2b\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e0b\u0e35 \u0e01\u0e24\u0e29\u0e13\u0e32\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 112\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0645569000733\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e08\u0e19\u0e30\u0e1a\u0e39\u0e0a\u0e32\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000733 \u0e1a\u0e08.\u0e2d\u0e08\u0e19\u0e30\u0e1a\u0e39\u0e0a\u0e32\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0653569001096\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c2026\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001096 \u0e2b\u0e08.\u0e0a\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c2026 2569-07-10 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 212  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002221\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002221 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 196\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0705569003138\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e04 \u0e04\u0e2d\u0e25\u0e42\u0e17\u0e23\u0e25 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003138 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e04 \u0e04\u0e2d\u0e25\u0e42\u0e17\u0e23\u0e25 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 282  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002581\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e14\u0e07\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47733\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47733\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002581 \u0e1a\u0e08.\u0e41\u0e14\u0e07\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47733 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 205  \u0e16\u0e19\u0e19\u0e41\u0e2a\u0e07\u0e0a\u0e39\u0e42\u0e15 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006994\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39 \u0e42\u0e2d\u0e40\u0e04\u0e23\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006994 \u0e1a\u0e08.\u0e22\u0e39 \u0e42\u0e2d\u0e40\u0e04\u0e23\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e44\u0e1f) \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2a\u0e16\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007001\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e04\u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007001 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e04\u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (charge point operator : cpo) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 79\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007010\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e31\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007010 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e31\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e35\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charger) \u0e15\u0e39\u0e49\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e0a\u0e38\u0e14\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 (ess) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 (ems) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 (bms) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 79\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007036\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e32\u0e40\u0e08\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007036 \u0e1a\u0e08.\u0e40\u0e08\u0e32\u0e40\u0e08\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e21\u0e32\u0e25\u0e48\u0e32 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e07\u0e02\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e35\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 70\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007249\",\"name_th\":\"\u0e1a\u0e08. \u0e22\u0e39\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e04\u0e2d\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007249 \u0e1a\u0e08. \u0e22\u0e39\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e04\u0e2d\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e14\u0e41\u0e25\u0e30\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007257\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e22 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10772\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10772\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007257 \u0e1a\u0e08.\u0e27\u0e32\u0e22 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 10772 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e0b\u0e2d\u0e2a\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e0b\u0e2d\u0e2a\u0e1e\u0e23\u0e34\u0e01 \u0e0b\u0e2d\u0e2a\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e2a\u0e1a\u0e32\u0e23\u0e4c\u0e1a\u0e34\u0e04\u0e34\u0e27 \u0e0b\u0e2d\u0e2a\u0e40\u0e22\u0e47\u0e19\u0e15\u0e32\u0e42\u0e1f \u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e2a\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e42\u0e15\u0e4a\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e21\u0e32\u0e22\u0e2d\u0e07\u0e40\u0e19\u0e2a \u0e2a\u0e25\u0e31\u0e14\u0e04\u0e23\u0e35\u0e21 \u0e19\u0e49\u0e33\u0e2a\u0e25\u0e31\u0e14 \u88fd\u9020 130\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0763569000315\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e232802\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0763569000315 \u0e2b\u0e08.\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e232802 2569-07-10 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e28\u0e2f\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d  \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 94  \u0e16\u0e19\u0e19\u0e20\u0e39\u0e21\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569002948\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e01\u0e21\u0e25\u0e40\u0e1e\u0e47\u0e17\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002948 \u0e1a\u0e08.\u0e1e\u0e23\u0e01\u0e21\u0e25\u0e40\u0e1e\u0e47\u0e17\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e22\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 6\/17  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e31\u0e27\u0e19\u0e32 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002661\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002661 \u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/14  \u0e0b\u0e2d\u0e22 \u0e23\u0e27\u0e21\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e16\u0e19\u0e19\u0e01\u0e30\u0e42\u0e23\u0e21 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002670\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e38\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002670 \u0e1a\u0e08.\u0e02\u0e38\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 399  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0815569002041\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 5 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002041 \u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 5 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 127\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0815569002050\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e1a\u0e38\u0e4a\u0e01\u0e01\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002050 \u0e1a\u0e08.\u0e2d\u0e35\u0e1a\u0e38\u0e4a\u0e01\u0e01\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 425\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0815569002068\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002068 \u0e1a\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e01\u0e40\u0e40\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e40\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e40\u0e40\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e40\u0e0b\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e34\u0e49\u0e27\u0e2d\u0e34\u0e19(built-in)\u0e40\u0e40\u0e25\u0e30\u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u5efa\u8a2d 195\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569012802\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e01\u0e29\u0e31\u0e15\u0e23\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012802 \u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e01\u0e29\u0e31\u0e15\u0e23\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 19\/26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012837\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e24\u0e15\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012837 \u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e24\u0e15\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 90\/5  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e30 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012853\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e40\u0e04\u0e40\u0e27\u0e25\u0e18\u0e4c\u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012853 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e40\u0e04\u0e40\u0e27\u0e25\u0e18\u0e4c\u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/245  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e19\u0e32\u0e2a\u0e19\u0e18\u0e34\u0e4c \u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0843569001329\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e41\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001329 \u0e2b\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e41\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 2569-07-10 1000000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 55\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010231\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e42\u0e0b\u0e42\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010231 \u0e1a\u0e08.\u0e40\u0e17\u0e42\u0e0b\u0e42\u0e23 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 21\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010265\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010265 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 174\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0865569001207\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e07\u0e29\u0e4c\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1f\u0e23\u0e38\u0e4a\u0e15 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001207 \u0e1a\u0e08.\u0e1e\u0e07\u0e29\u0e4c\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1f\u0e23\u0e38\u0e4a\u0e15 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e25\u0e33\u0e44\u0e22 \u0e21\u0e30\u0e02\u0e32\u0e21 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e21\u0e31\u0e19\u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e31\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e1c\u0e31\u0e01\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 533\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001215\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e13\u0e38\u0e01\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001215 \u0e1a\u0e08.\u0e1b\u0e13\u0e38\u0e01\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001573\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e23\u0e2d\u0e38\u0e21\u0e32 \u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e2a\u0e01\u0e34\u0e19\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001573 \u0e2b\u0e08.\u0e2d\u0e23\u0e2d\u0e38\u0e21\u0e32 \u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e2a\u0e01\u0e34\u0e19 2569-07-10 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52\/2  \u0e16\u0e19\u0e19\u0e27\u0e38\u0e12\u0e34\u0e20\u0e39\u0e21\u0e342 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005601\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e40\u0e14\u0e23\u0e19\u0e17\u0e4c \u0e40\u0e1e\u0e25\u0e22\u0e4c\u0e1f\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005601 \u0e1a\u0e08.\u0e0a\u0e34\u0e25\u0e40\u0e14\u0e23\u0e19\u0e17\u0e4c \u0e40\u0e1e\u0e25\u0e22\u0e4c\u0e1f\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47640 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e0b\u0e2d\u0e22 4 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e19\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005619\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e21\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005619 \u0e1a\u0e08.\u0e21\u0e32\u0e21\u0e48\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47711 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32,\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01,\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e25\u0e2d\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e0b\u0e2d\u0e22 4 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e19\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005627\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e39\u0e25\u0e2a\u0e38\u0e02 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e17\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46434\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46434\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005627 \u0e1a\u0e08.\u0e1e\u0e39\u0e25\u0e2a\u0e38\u0e02 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e17\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46434 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e2a\u0e44\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e21\u0e49\u0e32\u0e42\u0e22\u0e01 \u0e0a\u0e34\u0e07\u0e0a\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e0b\u0e2d\u0e22 4 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e19\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005643\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e32\u0e40\u0e2d\u0e01 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005643 \u0e1a\u0e08.\u0e40\u0e2a\u0e32\u0e40\u0e2d\u0e01 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 41  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e1e\u0e23\u0e38 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005660\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e17\u0e2d\u0e07 \u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005660 \u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e17\u0e2d\u0e07 \u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e25\u0e31\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 215  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005678\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e35\u0e19\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005678 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e35\u0e19\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005686\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e25\u0e34\u0e14\u0e32\u0e23\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005686 \u0e1a\u0e08.\u0e04\u0e32\u0e25\u0e34\u0e14\u0e32\u0e23\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14, \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e48\u0e0a\u0e34\u0e49\u0e19 ,\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e21\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/176  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001028\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e14\u0e25\u0e1f\u0e35\u0e23\u0e48\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001028 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e14\u0e25\u0e1f\u0e35\u0e23\u0e48\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 9\/9   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0945569000722\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e38\u0e2a\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000722 \u0e1a\u0e08.\u0e2e\u0e38\u0e2a\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e31\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e21\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e1b\u0e35 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u4e0d\u52d5\u7523 124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0103569007226\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e32\u0e22\u0e43\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007226 \u0e2b\u0e08.\u0e0a\u0e32\u0e22\u0e43\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 339\/48  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e32\u0e19\u0e19\u0e01-\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e224 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007234\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e14\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007234 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e14\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-09 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/36  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e21.\u0e18\u0e19\u0e32\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007242\",\"name_th\":\"\u0e2b\u0e08.3\u0e44\u0e17\u0e22 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007242 \u0e2b\u0e08.3\u0e44\u0e17\u0e22 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c 2569-07-09 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/36  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e21.\u0e18\u0e19\u0e32\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007251\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007251 \u0e2b\u0e08.\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-09 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/36  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e21.\u0e18\u0e19\u0e32\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007307\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e21\u0e25\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007307 \u0e2b\u0e08.\u0e01\u0e21\u0e25\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-09 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/342  \u0e0b\u0e2d\u0e22 \u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e3420 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129447\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e44\u0e19\u0e19\u0e4c\u0e44\u0e19\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129447 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e44\u0e19\u0e19\u0e4c\u0e44\u0e19\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 579\/199  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129463\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49331\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49331\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129463 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49331 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30 \u0e41\u0e25\u0e30\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e4d\u0e49\u0e32 \u0e17\u0e32\u0e07\u0e17\u0e30\u0e40\u0e25 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 1674\/493  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129480\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1a\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129480 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e1a\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/30  \u0e0b\u0e2d\u0e22 \u0e04\u0e38\u0e49\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 6 \u0e16\u0e19\u0e19\u0e04\u0e38\u0e49\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129498\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129498 \u0e1a\u0e08.\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e17\u0e14\u0e25\u0e2d\u0e07 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1\/11  \u0e0b\u0e2d\u0e22 16 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129501\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e34\u0e23\u0e4c\u0e14\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129501 \u0e1a\u0e08.\u0e40\u0e19\u0e34\u0e23\u0e4c\u0e14\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e23\u0e31\u0e1a\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1e\u0e25\u0e07 \u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e32\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 91  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 96\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129528\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129528 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68202 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u4e0d\u52d5\u7523 203\/13  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2715 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129536\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129536 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 10751 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u88fd\u9020 203\/13  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2715 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129544\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c\u0e44\u0e23\u0e2a\u0e4c \u0e41\u0e2a\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129544 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c\u0e44\u0e23\u0e2a\u0e4c \u0e41\u0e2a\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 2\/296  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35 25 \u0e41\u0e22\u0e01 2-1-2-1-2 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e01\u0e34\u0e08 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129561 \u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e2d\u0e38\u0e14\u0e21\u0e01\u0e34\u0e08 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e37\u0e0a \u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/35  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01158 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129579\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e21\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129579 \u0e1a\u0e08.\u0e21\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e21\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e2a\u0e21 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/55  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1752 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129587\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129587 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180\/23  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 54 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129617\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129617 \u0e1a\u0e08.\u0e23\u0e35\u0e04\u0e31\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 87301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e07 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e34\u0e15\u0e43\u0e08 \u533b\u7642\u30fb\u798f\u7949 71\/39  \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129641\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e1a\u0e32\u0e22\u0e19\u0e4c\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18122\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18122\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129641 \u0e1a\u0e08.\u0e2d\u0e19\u0e38\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e1a\u0e32\u0e22\u0e19\u0e4c\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 18122 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e40\u0e25\u0e48\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 79  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 66\/6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129676\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e48\u0e32\u0e1b\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129676 \u0e1a\u0e08.\u0e40\u0e25\u0e48\u0e32\u0e1b\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 102\/190  \u0e0b\u0e2d\u0e22 \u0e2a\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e20\u0e32 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129706\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e2d\u0e2d\u0e14\u0e34\u0e42\u0e2d \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129706 \u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e2d\u0e2d\u0e14\u0e34\u0e42\u0e2d \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46522 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e25\u0e33\u0e42\u0e1e\u0e07\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54\/149  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 73 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129731\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e19\u0e08 42 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129731 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e19\u0e08 42 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22 \u0e07\u0e32\u0e19\u0e17\u0e33\u0e14\u0e49\u0e27\u0e22\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e33\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e04\u0e23\u0e34\u0e25\u0e34\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 1109\/42  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129757\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129757 \u0e1a\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62022 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 digital transformation cybersecutiry risk management \u60c5\u5831\u901a\u4fe1\u30fbit 91  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 65 \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129773\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e40\u0e14\u0e22\u0e4c \u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129773 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e40\u0e14\u0e22\u0e4c \u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 259\/231  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 71 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129811\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e25\u0e32 \u0e0a\u0e38\u0e14\u0e19\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129811 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e25\u0e32 \u0e0a\u0e38\u0e14\u0e19\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/80  \u0e0b\u0e2d\u0e22 \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129820\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e25\u0e15\u0e49\u0e32 \u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129820 \u0e1a\u0e08.\u0e40\u0e14\u0e25\u0e15\u0e49\u0e32 \u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e38\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e28 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e1b\u0e31\u0e4a\u0e21\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 929  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129838\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129838 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 3\/9  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e192 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129854\",\"name_th\":\"\u0e1a\u0e08. \u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129854 \u0e1a\u0e08. \u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69200 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 234\/154  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e19\u0e35\u0e42\u0e2d 2 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e0b\u0e2d\u0e22 21 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129862\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e4a\u0e0b \u0e1a\u0e2d\u0e21\u0e1a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129862 \u0e1a\u0e08.\u0e08\u0e39\u0e4a\u0e0b \u0e1a\u0e2d\u0e21\u0e1a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e19\u0e49\u0e33\u0e1b\u0e31\u0e48\u0e19 \u0e2a\u0e21\u0e39\u0e17\u0e15\u0e35\u0e49 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/1  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 53 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129871\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129871 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e17\u0e38\u0e01\u0e41\u0e1c\u0e19\u0e01\u0e44\u0e27\u0e49\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e14\u0e35\u0e22\u0e27 (erp) \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c (cloud server) \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 (software as a service : saas) \u60c5\u5831\u901a\u4fe1\u30fbit 81\/26  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35\u0e17\u0e32\u0e27\u0e19\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 18 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129889\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e40\u0e25\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129889 \u0e1a\u0e08.\u0e1e\u0e32\u0e40\u0e25\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e15\u0e23\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e27\u0e07\u0e0a\u0e30\u0e15\u0e32 \u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02 \u0e17\u0e33\u0e19\u0e32\u0e22\u0e42\u0e0a\u0e04\u0e0a\u0e30\u0e15\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e08\u0e35\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 12\/118  \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129901\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e25 \u0e40\u0e21\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129901 \u0e1a\u0e08.\u0e0b\u0e2d\u0e25 \u0e40\u0e21\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2a\u0e20\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 684\/18  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e2344 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129927\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e2a\u0e32\u0e07 \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129927 \u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e2a\u0e32\u0e07 \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 866\/29  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 60 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129994\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e19\u0e02\u0e19\u0e2a\u0e48\u0e07 2518 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129994 \u0e1a\u0e08.\u0e0b\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e07\u0e40\u0e04\u0e23\u0e19\u0e02\u0e19\u0e2a\u0e48\u0e07 2518 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u904b\u8f38\u30fb\u7269\u6d41 8\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130003\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e1e\u0e35.\u0e42\u0e2d.\u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130003 \u0e1a\u0e08.\u0e40\u0e04.\u0e1e\u0e35.\u0e42\u0e2d.\u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69200 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 108\/152  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130020\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e25\u0e2d\u0e27\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130020 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e25\u0e2d\u0e27\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 131\/95  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e25\u0e34\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e2d\u0e40\u0e27\u0e19\u0e34\u0e27 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130038\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e27\u0e20\u0e39\u0e21\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21002\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21002\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130038 \u0e1a\u0e08.\u0e19\u0e27\u0e20\u0e39\u0e21\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 21002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 1850  \u0e0b\u0e2d\u0e22 \u0e2d\u0e23\u0e38\u0e13\u0e2d\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c 36 \u0e16\u0e19\u0e19\u0e2d\u0e23\u0e38\u0e13\u0e2d\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130046\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e25\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130046 \u0e1a\u0e08.\u0e01\u0e25\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e2a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e1e\u0e27\u0e07\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 527  \u0e0b\u0e2d\u0e22 \u0e41\u0e1a\u0e19\u0e0a\u0e30\u0e42\u0e14 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130054\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e2a\u0e40\u0e17\u0e04 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e22\u0e39\u0e17\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130054 \u0e1a\u0e08.\u0e41\u0e21\u0e2a\u0e40\u0e17\u0e04 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e22\u0e39\u0e17\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e1b\u0e23\u0e2a\u0e20\u0e32\u0e1e \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2a\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e33\u0e23\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33 \u0e25\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e04\u0e21\u0e35\u0e08\u0e32\u0e01\u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e4a\u0e32\u0e0b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e21\u0e32\u0e13\u0e39\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 74  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 48 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130062\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e17\u0e35\u0e19 \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130062 \u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c\u0e17\u0e35\u0e19 \u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 339\/95  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130089\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e38\u0e25\u0e08\u0e33\u0e40\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130089 \u0e1a\u0e08.\u0e08\u0e38\u0e25\u0e08\u0e33\u0e40\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 20\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 5 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130097\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39-\u0e14\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130097 \u0e1a\u0e08.\u0e22\u0e39-\u0e14\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/201  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130186\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e41\u0e04\u0e23\u0e4c \u0e41\u0e2d\u0e25\u0e1f\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130186 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e41\u0e04\u0e23\u0e4c \u0e41\u0e2d\u0e25\u0e1f\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19  \u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b  \u0e41\u0e01\u0e48\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a \u533b\u7642\u30fb\u798f\u7949 1976  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130208\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e2d\u0e2d\u0e1f \u0e40\u0e25\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130208 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e2d\u0e2d\u0e1f \u0e40\u0e25\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46414 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e40\u0e01\u0e49\u0e32 62 (\u0e0b\u0e2d\u0e228\u0e40\u0e2a\u0e23\u0e358) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130216\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e4c 1989 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130216 \u0e1a\u0e08.\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e4c 1989 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e15\u0e38\u0e4a\u0e01\u0e15\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 301\/701  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 68 (\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130232\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130232 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e32\u0e1c\u0e25\u0e32\u0e0d\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e0a\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e41\u0e1f \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e21\u0e32\u0e08\u0e32\u0e01\u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 288\/20  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 the edition \u0e2a\u0e32\u0e17\u0e23-\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 33 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130259\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e41\u0e04\u0e1b\u0e34\u0e15\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66301\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66301\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130259 \u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e32\u0e27\u0e31\u0e13 \u0e41\u0e04\u0e1b\u0e34\u0e15\u0e2d\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 66301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e38\u0e49\u0e19 \u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e1a\u0e31\u0e15\u0e23 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e14\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 555\/23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e1e\u0e35 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 (\u0e40\u0e2d\u0e01\u0e21\u0e31\u0e22) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130267\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130267 \u0e1a\u0e08.\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e32\u0e07\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e35\u0e25\u0e21\u0e40\u0e2d\u0e08  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s10063 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130275\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e07\u0e14\u0e32\u0e27\u0e17\u0e2d\u0e0799 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130275 \u0e1a\u0e08.\u0e27\u0e31\u0e07\u0e14\u0e32\u0e27\u0e17\u0e2d\u0e0799 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46313 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e34\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/533  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 52\u0e41\u0e22\u0e0133 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130313\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e27\u0e40\u0e08\u0e34\u0e14\u0e08\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130313 \u0e1a\u0e08.\u0e14\u0e32\u0e27\u0e40\u0e08\u0e34\u0e14\u0e08\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2898\/262  \u0e2d\u0e32\u0e04\u0e32\u0e23the capital ekamai-thonglor \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130321\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e14\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130321 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e14\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34 \u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 59\/15  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130348\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e34\u0e08\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e23\u0e31\u0e2a\u0e15\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130348 \u0e1a\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e34\u0e08\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e23\u0e31\u0e2a\u0e15\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 558  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130356\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e42\u0e0b\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130356 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e42\u0e0b\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (marketplace) \u0e42\u0e0b\u0e40\u0e0b\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130364\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130364 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 319  \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130399\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e47\u0e1a\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130399 \u0e1a\u0e08.\u0e41\u0e01\u0e47\u0e1a\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 208  \u0e0b\u0e2d\u0e22 \u0e21\u0e2b\u0e32\u0e28\u0e32\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130402\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e21\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130402 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e21\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e17\u0e38\u0e19 \u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e41\u0e01\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e25\u0e07\u0e17\u0e38\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 393  \u0e2d\u0e32\u0e04\u0e32\u0e23393 \u0e2a\u0e35\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130429\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e40\u0e04 \u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130429 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e40\u0e04 \u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/6  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.\u0e59 \u0e0b.8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130437\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e41\u0e19\u0e1b  \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46614\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46614\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130437 \u0e1a\u0e08.\u0e2a\u0e41\u0e19\u0e1b  \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46614 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 638  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130445\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1a\u0e35\u0e40\u0e2d\u0e2a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130445 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1a\u0e35\u0e40\u0e2d\u0e2a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 807-809  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e35\u0e25\u0e21\u0e40\u0e0b\u0e35\u0e48\u0e22\u0e07\u0e44\u0e2e\u0e49  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e2a\u0e35\u0e25\u0e21 17 \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e25\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130488\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e1b\u0e4c\u0e40\u0e1e\u0e01\u0e0b\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130488 \u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e1b\u0e4c\u0e40\u0e1e\u0e01\u0e0b\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (automation system) \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 28\/1  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 2 \u0e0b\u0e2d\u0e22 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130496\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e41\u0e1a\u0e23\u0e34\u0e48\u0e07 369 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130496 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e41\u0e1a\u0e23\u0e34\u0e48\u0e07 369 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e25\u0e39\u0e01\u0e1b\u0e37\u0e19 (bearing) \u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19 \u0e42\u0e0b\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/729  \u0e0b\u0e2d\u0e22 \u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130534\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130534 \u0e1a\u0e08.\u0e23\u0e35 \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 70209 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 107\/333  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e27\u0e34\u0e19\u0e17\u0e27\u0e07\u0e28\u0e4c 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130542\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130542 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u5efa\u8a2d 338  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 3 \u0e0b\u0e2d\u0e22 19 \u0e41\u0e22\u0e01 6-16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130551\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130551 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/2 \u0e15\u0e23\u0e2d\u0e01\u0e2a\u0e2d\u0e07\u0e1e\u0e23\u0e30  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130577\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e17 \u0e42\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130577 \u0e1a\u0e08.\u0e40\u0e1f\u0e17 \u0e42\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47640 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/5  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 2 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130631\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e2d\u0e40\u0e23\u0e17\u0e35\u0e1f \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130631 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e2d\u0e40\u0e23\u0e17\u0e35\u0e1f \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e0a\u0e19\u0e34\u0e14\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 89\/248  \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130658\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130658 \u0e1a\u0e08.\u0e14\u0e33\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 933  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 75 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130666\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e32 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130666 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e32 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 63\/4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130674\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130674 \u0e1a\u0e08.\u0e27\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 45301 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 130  \u0e0b\u0e2d\u0e22 \u0e17\u0e38\u0e48\u0e07\u0e21\u0e31\u0e07\u0e01\u0e23 22 \u0e16\u0e19\u0e19\u0e17\u0e38\u0e48\u0e07\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130691\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e25\u0e34\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e35\u0e21 \u0e40\u0e1e\u0e25\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130691 \u0e1a\u0e08.\u0e2d\u0e35\u0e25\u0e34\u0e17 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e35\u0e21 \u0e40\u0e1e\u0e25\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e41\u0e15\u0e49\u0e21\u0e2a\u0e30\u0e2a\u0e21\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (digital points\/ coins) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2089\/15  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130704\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e13\u0e28\u0e34\u0e23\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130704 \u0e1a\u0e08.\u0e1e\u0e34\u0e13\u0e28\u0e34\u0e23\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 319  \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130739\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130739 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 4  \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d 25 \u0e41\u0e22\u0e01 2-4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130747\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85493\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85493\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130747 \u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 85493 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e01\u0e27\u0e14\u0e27\u0e34\u0e0a\u0e32 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e20\u0e32\u0e04\u0e1b\u0e01\u0e15\u0e34) \u6559\u80b2 288\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25-\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e212 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130755\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130755 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 98\/39  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130763\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e23\u0e14 \u0e1a\u0e31\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130763 \u0e1a\u0e08.\u0e40\u0e1a\u0e23\u0e14 \u0e1a\u0e31\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 775  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e04\u0e34\u0e07 \u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e21\u0e2d\u0e25\u0e25\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a208 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130771\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e40\u0e0a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130771 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e40\u0e0a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 77109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e1e\u0e48\u0e27\u0e07 \u0e23\u0e16\u0e01\u0e36\u0e48\u0e07\u0e1e\u0e48\u0e27\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 85\/13  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 79 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130801\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e40\u0e01\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0105569130801 \u0e1a\u0e08.\u0e41\u0e01\u0e49\u0e27\u0e40\u0e01\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49323 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e42\u0e14\u0e22\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e23\u0e48\u0e27\u0e21\u0e27\u0e34\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 99\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0105569130810\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e23\u0e32\u0e17\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130810 \u0e1a\u0e08.\u0e2a\u0e15\u0e23\u0e32\u0e17\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e14 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e33\u0e19\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u91d1\u878d\u30fb\u4fdd\u967a 4\/244  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 40 (\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130828\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1e\u0e25\u0e32\u0e23\u0e34\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130828 \u0e1a\u0e08.\u0e42\u0e1e\u0e25\u0e32\u0e23\u0e34\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e43\u0e14 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e33\u0e19\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u91d1\u878d\u30fb\u4fdd\u967a 4\/244  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 40 (\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130836\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e14\u0e1b\u0e23\u0e32\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130836 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e14\u0e1b\u0e23\u0e32\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e15\u0e32\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e02\u0e19\u0e21 \u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90\/298  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 26 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130844\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e2d \u0e1e\u0e32\u0e23\u0e32\u0e0a\u0e39\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11049\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11049\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130844 \u0e1a\u0e08.\u0e40\u0e25\u0e2d \u0e1e\u0e32\u0e23\u0e32\u0e0a\u0e39\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 11049 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07  \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01  \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21  \u0e19\u0e49\u0e33\u0e01\u0e25\u0e31\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48  \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u88fd\u9020 5\/49  \u0e0b\u0e2d\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002283\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e25\u0e32\u0e40\u0e15\u0e49\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002283 \u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e25\u0e32\u0e40\u0e15\u0e49 2569-07-09 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002291\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e32\u0e27\u0e23\u0e23\u0e13\u0e42\u0e04\u0e42\u0e04\u0e01\u0e23\u0e35\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002291 \u0e2b\u0e08.\u0e25\u0e32\u0e27\u0e23\u0e23\u0e13\u0e42\u0e04\u0e42\u0e04\u0e01\u0e23\u0e35\u0e19 2569-07-09 1000000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 747\/447  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002305\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e33\u0e1e\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002305 \u0e2b\u0e08.\u0e01\u0e33\u0e1e\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-09 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 747\/447  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002321\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 59 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002321 \u0e2b\u0e08.\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 59 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 885\/129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022693\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e42\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022693 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e42\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 28299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u88fd\u9020 936  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022723\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022723 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46102 \u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022731\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e24\u0e15\u0e0a\u0e0d\u0e32 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022731 \u0e1a\u0e08.\u0e01\u0e24\u0e15\u0e0a\u0e0d\u0e32 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e16\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e02\u0e31\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 435\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022766\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e14\u0e35\u0e25 \u0e40\u0e2d\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022766 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e14\u0e35\u0e25 \u0e40\u0e2d\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 78\/243  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022774\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e2d\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022774 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e2d\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7  \u0e0b\u0e2d\u0e22 2(\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e49\u0e27\u0e22\u0e2e\u0e31\u0e49\u0e27) \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e25\u0e27\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022782\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e32\u0e22\u0e1f\u0e39\u0e48 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82920\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82920\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022782 \u0e1a\u0e08.\u0e09\u0e32\u0e22\u0e1f\u0e39\u0e48 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 82920 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 115\/78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022791\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2b\u0e39 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022791 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2b\u0e39 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 59202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e42\u0e0a\u0e27\u0e4c\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e31\u0e01\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 461\/118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022821\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e23\u0e35\u0e42\u0e19\u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022821 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e23\u0e35\u0e42\u0e19\u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 4\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 47 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022839\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e23\u0e34\u0e0a \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10499\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10499\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022839 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e23\u0e34\u0e0a \u0e2d\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 10499 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 559\/166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022847\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e01 \u0e1a\u0e23\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022847 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e01 \u0e1a\u0e23\u0e34\u0e25\u0e40\u0e25\u0e35\u0e22\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35 \u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u5bbf\u6cca\u30fb\u98f2\u98df 78\/58  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e01\u0e34\u0e48\u0e07\u0e41\u0e01\u0e49\u0e27-\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e0b\u0e2d\u0e22 \u0e08\u0e07\u0e28\u0e34\u0e23\u0e34 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35-\u0e15\u0e33\u0e2b\u0e23\u0e38 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022871\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e1e\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022871 \u0e1a\u0e08.\u0e1e\u0e31\u0e1e\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/232  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e17\u0e2d\u0e07 3 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022880\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e35 (\u0e44\u0e21\u0e48)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022880 \u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e35 (\u0e44\u0e21\u0e48)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 829\/343  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022944\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e42\u0e23\u0e25\u0e32  \u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022944 \u0e1a\u0e08.\u0e08\u0e35\u0e42\u0e23\u0e25\u0e32  \u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e01\u0e49\u0e32\u0e19\u0e2b\u0e2d\u0e21  \u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 225  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022952\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e27\u0e34\u0e19\u0e14\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022952 \u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e27\u0e34\u0e19\u0e14\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 64202 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 (activities of holding companies, of mostly investing in non-financial sectors) \u91d1\u878d\u30fb\u4fdd\u967a 304\/198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022961\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e17\u0e32\u0e25\u0e34\u0e2a\u0e15\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022961 \u0e1a\u0e08.\u0e41\u0e04\u0e17\u0e32\u0e25\u0e34\u0e2a\u0e15\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 64202 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 (activities of holding companies, of mostly investing in non-financial sectors) \u91d1\u878d\u30fb\u4fdd\u967a 304\/198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025676\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025676 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e01\u0e21 \u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 27\/144  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025684\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e31\u0e19\u0e08\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025684 \u0e1a\u0e08.\u0e09\u0e31\u0e19\u0e08\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 18  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e19\u0e19\u0e17\u0e4c 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025692\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e42\u0e27\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025692 \u0e1a\u0e08.\u0e1e\u0e34\u0e42\u0e27\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 82990 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e19\u0e33 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21  \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 999\/161  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025706\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e40\u0e04 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025706 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e40\u0e04 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e42\u0e14\u0e22\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 22 \u0e41\u0e22\u0e01 11\/3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025722\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025722 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/279  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025731\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e17 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025731 \u0e1a\u0e08.\u0e40\u0e0b\u0e47\u0e17 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025773\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19.\u0e04\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025773 \u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19.\u0e04\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 5\/2054  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 63 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025803\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025803 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47595 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e25\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/70  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 31 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025811\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e19\u0e34\u0e0a\u0e40\u0e25\u0e49\u0e07\u0e41\u0e0b\u0e48\u0e1a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e30\u0e40\u0e1e\u0e23\u0e32\u0e40\u0e1c\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025811 \u0e1a\u0e08.\u0e27\u0e32\u0e19\u0e34\u0e0a\u0e40\u0e25\u0e49\u0e07\u0e41\u0e0b\u0e48\u0e1a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e30\u0e40\u0e1e\u0e23\u0e32\u0e40\u0e1c\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 105\/82  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e19\u0e17\u0e23\u0e35 \u0e1f\u0e25\u0e2d\u0e23\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025820\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e23\u0e14999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"53200\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"53200\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025820 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e23\u0e14999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 53200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 71\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025838\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21.\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2559 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025838 \u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21.\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2559 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49334 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a?\u0e2a\u0e48\u0e07 \u0e22\u0e01 \u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e25\u0e32\u0e01\u0e08\u0e39\u0e07 \u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e21\u0e2d\u0e1a\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32?\u0e2d\u0e2d\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e19\u0e15\u0e39\u0e49 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19  \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 99\/313  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025846\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e0b\u0e31\u0e19\u0e2a\u0e4c \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025846 \u0e1a\u0e08.\u0e17\u0e23\u0e35\u0e0b\u0e31\u0e19\u0e2a\u0e4c \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 25119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e32\u0e27\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e23\u0e32\u0e27\u0e01\u0e31\u0e19\u0e15\u0e01 \u0e23\u0e31\u0e49\u0e27 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2a\u0e40\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 33\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025854\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e40\u0e25\u0e01\u0e49\u0e32 \u0e14\u0e35\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025854 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e40\u0e25\u0e01\u0e49\u0e32 \u0e14\u0e35\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47222 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e  \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67\/1044  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025862\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e15\u0e35\u0e4b\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025862 \u0e1a\u0e08.\u0e1e\u0e25\u0e15\u0e35\u0e4b\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 39\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025871\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025871 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e42\u0e22\u0e18\u0e32\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1\/175  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025927\",\"name_th\":\"\u0e1a\u0e08.4\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (2569) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025927 \u0e1a\u0e08.4\u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (2569) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 125\/92  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e13\u0e32\u0e2a\u0e34\u0e23\u0e34 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025935\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e25\u0e37\u0e49\u0e21\u0e08\u0e34\u0e15\u0e15\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025935 \u0e1a\u0e08.\u0e1b\u0e25\u0e37\u0e49\u0e21\u0e08\u0e34\u0e15\u0e15\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u4e0d\u52d5\u7523 35\/1,35\/2,36\/1,36\/2,36\/3  \u0e0b\u0e2d\u0e22 \u0e2d\u0e31\u0e0d\u0e0a\u0e25\u0e356,8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025978\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025978 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5efa\u8a2d 165\/339  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025994\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e38\u0e01\u0e19\u0e38\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025994 \u0e1a\u0e08.\u0e19\u0e38\u0e01\u0e19\u0e38\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u60c5\u5831\u901a\u4fe1\u30fbit 129\/387  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026001\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e1a\u0e1a\u0e35\u0e49\u0e1a\u0e25\u0e39 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026001 \u0e1a\u0e08.\u0e41\u0e2d\u0e4a\u0e1a\u0e1a\u0e35\u0e49\u0e1a\u0e25\u0e39 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 70209 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 114\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026010\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026010 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e25\u0e30\u0e04\u0e23 \u0e07\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e07\u0e32\u0e19\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e07\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 119\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002313\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e07\u0e04\u0e25\u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002313 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e07\u0e04\u0e25\u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c 2569-07-09 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e17\u0e33\u0e2a\u0e35\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021123\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021123 \u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/334  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021140\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e42\u0e19 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021140 \u0e1a\u0e08.\u0e23\u0e35\u0e42\u0e19 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 38\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021174\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e42\u0e04\u0e49\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021174 \u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e42\u0e04\u0e49\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021182\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021182 \u0e1a\u0e08.\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27 \u0e46 \u0e44\u0e1b \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d  \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 133\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021191\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e49\u0e2d\u0e14\u0e42\u0e1a\u0e23 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021191 \u0e1a\u0e08.\u0e04\u0e27\u0e49\u0e2d\u0e14\u0e42\u0e1a\u0e23 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 74200 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e21\u0e38\u0e21\u0e2a\u0e39\u0e07\u0e42\u0e14\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e44\u0e23\u0e49\u0e04\u0e19\u0e02\u0e31\u0e1a \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 153\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021221\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e04 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021221 \u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e04 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021263\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021263 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67\/111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021271\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e42\u0e21\u0e1a\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021271 \u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e4c \u0e42\u0e21\u0e1a\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e34\u0e21\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e0b\u0e34\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021280\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021280 \u0e1a\u0e08.\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68102 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u4e0d\u52d5\u7523 445\/147  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021301\",\"name_th\":\"\u0e1a\u0e08.10 \u0e04\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021301 \u0e1a\u0e08.10 \u0e04\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 (\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c-\u0e0b\u0e2d\u0e1f\u0e17\u0e4c\u0e41\u0e27\u0e23\u0e4c) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021310\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e18\u0e32\u0e23\u0e32 \u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021310 \u0e1a\u0e08.\u0e20\u0e39\u0e18\u0e32\u0e23\u0e32 \u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e0d\u0e49\u0e32 \u0e2a\u0e27\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/666  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021336\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e47\u0e01\u0e0b\u0e34\u0e19\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021336 \u0e1a\u0e08.\u0e40\u0e27\u0e47\u0e01\u0e0b\u0e34\u0e19\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 198\/76  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0b\u0e47\u0e19\u0e42\u0e17\u0e23 \u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c-345 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021344\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021344 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 72\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004466\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e09\u0e31\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63990\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63990\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004466 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e09\u0e31\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 63990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e41\u0e04\u0e2a\u0e15\u0e4c\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 421\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004474\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e19\u0e15\u0e4c\u0e2a\u0e34\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52241\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52241\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004474 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e19\u0e15\u0e4c\u0e2a\u0e34\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 52241 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e22\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e25\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e43\u0e19\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e43\u0e19\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 497\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004482\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e42\u0e23\u0e08\u0e19\u0e30 33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004482 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e42\u0e23\u0e08\u0e19\u0e30 33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 302\/81-82  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004491\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e27\u0e27 \u0e1b\u0e25\u0e32\u0e0b\u0e34\u0e48\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10211\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10211\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004491 \u0e1a\u0e08.\u0e41\u0e27\u0e27 \u0e1b\u0e25\u0e32\u0e0b\u0e34\u0e48\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 10211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1b\u0e25\u0e32\u0e2a\u0e14 \u0e1b\u0e25\u0e32\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e1b\u0e25\u0e32\u0e41\u0e0a\u0e48\u0e40\u0e40\u0e02\u0e47\u0e07 \u88fd\u9020 9\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004504\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e23\u0e34\u0e19\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004504 \u0e1a\u0e08.\u0e04\u0e34\u0e23\u0e34\u0e19\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19\\\"\\\" \u4e0d\u52d5\u7523 48\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004512\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004512 \u0e1a\u0e08.\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 99\/216  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004521\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004521 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43210 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u5efa\u8a2d 32\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001564\",\"name_th\":\"\u0e1a\u0e08.\u0e0a.\u0e0a\u0e31\u0e22\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001564 \u0e1a\u0e08.\u0e0a.\u0e0a\u0e31\u0e22\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 538  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000744\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 2569\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000744 \u0e2b\u0e08.\u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 2569 2569-07-09 1000000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 107\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000752\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e18\u0e19\u0e0a\u0e31\u0e22 \u0e02\u0e19\u0e2a\u0e48\u0e07\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000752 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e18\u0e19\u0e0a\u0e31\u0e22 \u0e02\u0e19\u0e2a\u0e48\u0e07 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 8\/6  \u0e0b\u0e2d\u0e22 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002932\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e48\u0e2a\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002932 \u0e2b\u0e08.\u0e1e\u0e35\u0e48\u0e2a\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-09 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 193\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002941\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 1888\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002941 \u0e2b\u0e08.\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 1888 2569-07-09 1000000 47912 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/67  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036081\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e27\u0e31\u0e15\u0e15\u0e4c \u0e42\u0e0b\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036081 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e27\u0e31\u0e15\u0e15\u0e4c \u0e42\u0e0b\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e25\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 (battery swapping station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 37\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036090\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e17\u0e3327 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036090 \u0e1a\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e17\u0e3327 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 98\/22  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e1a\u0e49\u0e32\u0e19\u0e28\u0e38\u0e20\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036111\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e0b\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036111 \u0e1a\u0e08.\u0e44\u0e27\u0e17\u0e4c\u0e0b\u0e31\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e02\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 836\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036120\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e40\u0e17\u0e40\u0e25\u0e04\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036120 \u0e1a\u0e08.\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e40\u0e17\u0e40\u0e25\u0e04\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u5efa\u8a2d 316\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036138\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036138 \u0e1a\u0e08.\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 207\/194  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036201\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e23\u0e16\u0e22\u0e01 \u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52214\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52214\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036201 \u0e1a\u0e08.\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e23\u0e16\u0e22\u0e01 \u0e41\u0e2b\u0e25\u0e21\u0e09\u0e1a\u0e31\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 52214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c\u0e2d\u0e2d\u0e19 \u0e23\u0e16\u0e25\u0e32\u0e01\u0e08\u0e39\u0e07 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e40\u0e2e\u0e35\u0e4a\u0e22\u0e1a \u0e23\u0e16\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e23\u0e16\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 271\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036219\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e40\u0e08 \u0e42\u0e2e\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036219 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e40\u0e08 \u0e42\u0e2e\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036227\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e1a\u0e35 \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036227 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e1a\u0e35 \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 16\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036235\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e24\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036235 \u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e24\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e22\u0e32\u0e07\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e30\u0e22\u0e32\u0e07 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e22\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 225  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036243\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e47\u0e2d\u0e1a\u0e1a\u0e34\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036243 \u0e1a\u0e08.\u0e27\u0e47\u0e2d\u0e1a\u0e1a\u0e34\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 117\/81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036294\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e21\u0e31\u0e25\u0e15\u0e34\u0e04\u0e2d\u0e23\u0e4c\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036294 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e21\u0e31\u0e25\u0e15\u0e34\u0e04\u0e2d\u0e23\u0e4c\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e04\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u0e1f\u0e34\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036308\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e1f \u0e21\u0e2d\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036308 \u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e1f \u0e21\u0e2d\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 492\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036324\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e23\u0e2a\u0e15\u0e49\u0e32 \u0e1e\u0e23\u0e4a\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036324 \u0e1a\u0e08.\u0e40\u0e1e\u0e23\u0e2a\u0e15\u0e49\u0e32 \u0e1e\u0e23\u0e4a\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e04\u0e23\u0e2d\u0e07\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e14\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 145\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036341\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e2a\u0e01\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e23\u0e2d\u0e19\u0e40\u0e21\u0e19\u0e17\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81291\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81291\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036341 \u0e1a\u0e08.\u0e1a\u0e25\u0e39 \u0e2a\u0e01\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e23\u0e2d\u0e19\u0e40\u0e21\u0e19\u0e17\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 81291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e41\u0e21\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e23\u0e33\u0e04\u0e32\u0e0d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 666\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036391\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e04\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036391 \u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e04\u0e19\u0e14\u0e4c\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e42\u0e0b\u0e25\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u5efa\u8a2d 70\/190  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036405\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34\u0e25\u0e23\u0e39\u0e1a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036405 \u0e1a\u0e08.\u0e14\u0e34\u0e25\u0e23\u0e39\u0e1a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036421\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e22\u0e33\u0e41\u0e0b\u0e48\u0e1a\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036421 \u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e22\u0e33\u0e41\u0e0b\u0e48\u0e1a\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2e\u0e2d\u0e25\u0e4c (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19  \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e14\u0e34\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 e-commerce \u5bbf\u6cca\u30fb\u98f2\u98df 130\/2  \u0e16\u0e19\u0e19\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e25\u0e32\u0e21 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036430\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e27\u0e31\u0e0d\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036430 \u0e1a\u0e08.\u0e02\u0e27\u0e31\u0e0d\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 83\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036456\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e25\u0e25\u0e30\u0e21\u0e38\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036456 \u0e1a\u0e08.\u0e0a\u0e25\u0e25\u0e30\u0e21\u0e38\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e42\u0e14\u0e22\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e08\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 88\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036464\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e2a\u0e1b\u0e35\u0e14 \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036464 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e2a\u0e1b\u0e35\u0e14 \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e19\u0e4c \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 565\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036481\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e23\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036481 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e23\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 245\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036502\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e2a.\u0e40\u0e04. \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04\u0e04\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43222\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43222\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036502 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e2a.\u0e40\u0e04. \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04\u0e04\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e01\u0e4a\u0e32\u0e0b \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e25\u0e31\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e41\u0e25\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u5efa\u8a2d 11\/84  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009157\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e2a\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009157 \u0e1a\u0e08.\u0e1f\u0e2d\u0e2a\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46900 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009165\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e22\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009165 \u0e1a\u0e08.\u0e23\u0e32\u0e22\u0e32 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1d\u0e32\u0e01 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/50  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e04\u0e15\u0e2d\u0e40\u0e23\u0e35\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009173\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009173 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 44\/214  \u0e16\u0e19\u0e19\u0e27\u0e31\u0e14\u0e42\u0e02\u0e14\u0e2b\u0e34\u0e19-\u0e40\u0e02\u0e32\u0e44\u0e1c\u0e48 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009181\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009181 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e25\u0e36\u0e07 \u0e01\u0e31\u0e14 \u0e1b\u0e31\u0e4a\u0e21 \u0e40\u0e08\u0e35\u0e22\u0e23 \u0e04\u0e32\u0e23\u0e4c\u0e44\u0e1a\u0e15\u0e4c \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e15\u0e31\u0e14 \u0e1e\u0e31\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 710  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002161\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e40\u0e21\u0e0b\u0e14\u0e4c \u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002161 \u0e1a\u0e08.\u0e2d\u0e30\u0e40\u0e21\u0e0b\u0e14\u0e4c \u0e41\u0e1a\u0e21\u0e1a\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e49\u0e44\u0e1c\u0e48 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002179\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e40\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002179 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e40\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 88\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003701\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003701 \u0e1a\u0e08.\u0e40\u0e2d\u0e1f\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e23\u0e27\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 865  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0275569001105\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e1b\u0e23\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001105 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e1b\u0e23\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 554  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002672\",\"name_th\":\"\u0e2b\u0e08.\u0e22\u0e38\u0e17\u0e18\u0e19\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002672 \u0e2b\u0e08.\u0e22\u0e38\u0e17\u0e18\u0e19\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 2569-07-09 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180\/3  \u0e16\u0e19\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e23\u0e07\u0e04\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002681\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2b\u0e22\u0e32 \u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 20\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47749\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47749\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002681 \u0e2b\u0e08.\u0e40\u0e2b\u0e22\u0e32 \u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07 20 2569-07-09 1000000 47749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 339  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007111\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e04\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007111 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e04\u0e2d\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 56  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e42\u0e1e\u0e18\u0e34\u0e4c\u0e17\u0e2d\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007129\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e32\u0e27\u0e23 \u0e0b\u0e31\u0e04\u0e40\u0e0b\u0e2a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007129 \u0e1a\u0e08.\u0e16\u0e32\u0e27\u0e23 \u0e0b\u0e31\u0e04\u0e40\u0e0b\u0e2a \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e44\u0e21\u0e49\u0e0b\u0e38\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 151  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007137\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007137 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23  \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23-\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 1000\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007145\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c 1688 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007145 \u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c 1688 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007153\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e31\u0e15\u0e16\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007153 \u0e1a\u0e08.\u0e18\u0e19\u0e31\u0e15\u0e16\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46699 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e41\u0e1b\u0e23\u0e2a\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01  \u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e41\u0e01\u0e49\u0e27 \u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007161\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e27\u0e31\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007161 \u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e27\u0e31\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007170\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e07\u0e20\u0e31\u0e04\u0e28\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007170 \u0e1a\u0e08.\u0e1e\u0e07\u0e20\u0e31\u0e04\u0e28\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 421  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001005\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e30\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e27\u0e39\u0e4a\u0e14\u0e0a\u0e34\u0e1e\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001005 \u0e2b\u0e08.\u0e21\u0e30\u0e40\u0e1f\u0e37\u0e2d\u0e07\u0e27\u0e39\u0e4a\u0e14\u0e0a\u0e34\u0e1e 2569-07-09 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e2a\u0e31\u0e1a\u0e44\u0e21\u0e49\u0e40\u0e1a\u0e0d\u0e08\u0e1e\u0e23\u0e23\u0e0d\u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e22\u0e39\u0e04\u0e32 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e25\u0e39\u0e01\u0e02\u0e36\u0e49\u0e19\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30 13 \u0e0a\u0e19\u0e34\u0e14 , \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e44\u0e21\u0e49\u0e2a\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 244  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e30\u0e40\u0e1f\u0e37\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e192081 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0313569001013\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e27\u0e01\u0e23 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001013 \u0e2b\u0e08.\u0e28\u0e34\u0e27\u0e01\u0e23 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 2569-07-09 1000000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u88fd\u9020 222\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0335569001139\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e14\u0e41\u0e2b\u0e25\u0e21\u0e17\u0e2d\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001139 \u0e1a\u0e08.\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e14\u0e41\u0e2b\u0e25\u0e21\u0e17\u0e2d\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e14 \u4e0d\u52d5\u7523 513  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569001838\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e4a\u0e14\u0e27\u0e49\u0e32\u0e19\u0e0b\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001838 \u0e2b\u0e08.\u0e41\u0e2d\u0e4a\u0e14\u0e27\u0e49\u0e32\u0e19\u0e0b\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-09 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 303  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0343569001862\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e1e\u0e25\u0e31\u0e2a\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001862 \u0e2b\u0e08.\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e1e\u0e25\u0e31\u0e2a 2569-07-09 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 671  \u0e16\u0e19\u0e19\u0e0a\u0e22\u0e32\u0e07\u0e01\u0e39\u0e23 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003085\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e24\u0e15 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003085 \u0e1a\u0e08.\u0e01\u0e24\u0e15 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47732 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e17\u0e2d\u0e07 \u0e40\u0e07\u0e34\u0e19 \u0e19\u0e32\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73  \u0e16\u0e19\u0e19\u0e0a\u0e22\u0e32\u0e07\u0e01\u0e39\u0e23 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003093\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e0b\u0e35\u0e48 \u0e40\u0e14\u0e22\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003093 \u0e1a\u0e08.\u0e40\u0e14\u0e0b\u0e35\u0e48 \u0e40\u0e14\u0e22\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 789\/83  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e32\u0e23\u0e34\u0e19 \u0e42\u0e19\u0e27\u0e48\u0e32 \u0e14\u0e2d\u0e19\u0e41\u0e04 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003115\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e35\u0e19\u0e2a\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003115 \u0e1a\u0e08.\u0e22\u0e35\u0e19\u0e2a\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e22\u0e35\u0e19\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47\u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/2  \u0e0b\u0e2d\u0e22 \u0e1e\u0e19\u0e21 5 \u0e16\u0e19\u0e19\u0e1e\u0e19\u0e21 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003123\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003123 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e14 \u0e21\u0e31\u0e19\u0e40\u0e2a\u0e49\u0e19 \u0e21\u0e31\u0e19\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e17\u0e33\u0e25\u0e32\u0e19\u0e15\u0e32\u0e01\\\" \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e22\u0e32\u0e27 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003166\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c888 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003166 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c888 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0363569000866\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e07 2026\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000866 \u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e07 2026 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 267  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0395569000442\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e19\u0e34\u0e0a\u0e32 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000442 \u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e19\u0e34\u0e0a\u0e32 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0403569003040\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003040 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 151  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006571\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e22\u0e32\u0e1e\u0e37\u0e0a\u0e1e\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006571 \u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e22\u0e32\u0e1e\u0e37\u0e0a\u0e1e\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001586\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2d\u0e04\u0e34\u0e27 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001586 \u0e2b\u0e08.\u0e44\u0e2d\u0e04\u0e34\u0e27 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-09 1000000 33200 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e48\u0e27\u0e07 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u88fd\u9020 186  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000768\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e38\u0e48\u0e07\u0e17\u0e2d\u0e07 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e01\u0e35\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01469\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01469\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000768 \u0e2b\u0e08.\u0e17\u0e38\u0e48\u0e07\u0e17\u0e2d\u0e07 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e01\u0e35\u0e49 \u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-09 1000000 01469 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e44\u0e01\u0e48\u0e07\u0e27\u0e07 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e40\u0e1e\u0e32\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e48\u0e2d\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e21\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e25\u0e39\u0e01\u0e44\u0e01\u0e48\u0e07\u0e27\u0e07 \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48\u0e07\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e1e\u0e25\u0e2d\u0e22\u0e44\u0e14\u0e49 \u0e08\u0e32\u0e01\u0e44\u0e01\u0e48\u0e07\u0e27\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e19 \u0e21\u0e39\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e07\u0e27\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u8fb2\u6797\u6c34\u7523 374  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001651\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001651 \u0e1a\u0e08.\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001669\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e25\u0e19 \u0e40\u0e14\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001669 \u0e1a\u0e08.\u0e0a\u0e25\u0e19 \u0e40\u0e14\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e14\u0e23\u0e2a\u0e2a\u0e32\u0e27\u0e1e\u0e25\u0e31\u0e2a\u0e44\u0e0b\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001677\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e16\u0e2a\u0e32\u0e22\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001677 \u0e1a\u0e08.\u0e23\u0e16\u0e2a\u0e32\u0e22\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0485569000883\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e20\u0e34\u0e2842 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000883 \u0e1a\u0e08.\u0e25\u0e32\u0e20\u0e34\u0e2842 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 381\/63  \u0e16\u0e19\u0e19\u0e19\u0e34\u0e15\u0e42\u0e22 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0493569000385\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 168\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0493569000385 \u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 168 2569-07-09 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 697  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004495\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e2d\u0e07\u0e40\u0e1a\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004495 \u0e2b\u0e08.\u0e02\u0e2d\u0e07\u0e40\u0e1a\u0e2a \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-09 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004576\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e17 \u0e0a\u0e2d\u0e1b\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004576 \u0e2b\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e17 \u0e0a\u0e2d\u0e1b 2569-07-09 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 78\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015456\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04 \u0e2d\u0e2d\u0e14\u0e34\u0e17\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015456 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04 \u0e2d\u0e2d\u0e14\u0e34\u0e17\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 190\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015464\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e07\u0e04\u0e4c \u0e40\u0e2e\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015464 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e07\u0e04\u0e4c \u0e40\u0e2e\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 259\/53  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015481\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e40\u0e25\u0e40\u0e01\u0e23\u0e35\u0e22 \u0e1a\u0e34\u0e2a\u0e42\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015481 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e40\u0e25\u0e40\u0e01\u0e23\u0e35\u0e22 \u0e1a\u0e34\u0e2a\u0e42\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 214-216  \u0e16\u0e19\u0e19\u0e41\u0e01\u0e49\u0e27\u0e19\u0e27\u0e23\u0e31\u0e10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015499\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e23\u0e32 \u0e42\u0e01\u0e25168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015499 \u0e1a\u0e08.\u0e27\u0e23\u0e32 \u0e42\u0e01\u0e25168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/351  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015502\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e35\u0e49\u0e22\u0e19 \u0e41\u0e0b\u0e07\u0e04\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015502 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e35\u0e49\u0e22\u0e19 \u0e41\u0e0b\u0e07\u0e04\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 546  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015511\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015511 \u0e1a\u0e08.\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 411\/35  \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e34\u0e2a\u0e0b\u0e48\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015561 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e34\u0e2a\u0e0b\u0e48\u0e32 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 382  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001391\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001391 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 25922 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e17\u0e33\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e42\u0e25\u0e2b\u0e30\u0e1c\u0e2a\u0e21 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 11\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001633\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e4b\u0e21\u0e2d\u0e34\u0e4b\u0e21 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e14\u0e19\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001633 \u0e1a\u0e08.\u0e2d\u0e38\u0e4b\u0e21\u0e2d\u0e34\u0e4b\u0e21 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e40\u0e14\u0e19\u0e17\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e1f\u0e31\u0e19 \u0e16\u0e2d\u0e19\u0e1f\u0e31\u0e19 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e32\u0e01\u0e1f\u0e31\u0e19 \u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e42\u0e23\u0e04\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1f\u0e31\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e32\u0e07\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u533b\u7642\u30fb\u798f\u7949 11-13  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e17\u0e31\u0e19\u0e43\u0e08 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0555569000572\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e34\u0e40\u0e27\u0e25\u0e25\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000572 \u0e1a\u0e08.\u0e2d\u0e35\u0e27\u0e34\u0e40\u0e27\u0e25\u0e25\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e2d\u0e31\u0e25\u0e15\u0e23\u0e49\u0e32\u0e0b\u0e32\u0e27\u0e14\u0e4c \u533b\u7642\u30fb\u798f\u7949 990\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0565569000581\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e31\u0e04\u0e08\u0e34\u0e23\u0e32789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000581 \u0e1a\u0e08.\u0e20\u0e31\u0e04\u0e08\u0e34\u0e23\u0e32789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 80100 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 125  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0573569002158\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e34\u0e23\u0e31\u0e13\u0e22\u0e4c\u0e21\u0e13\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002158 \u0e2b\u0e08.\u0e2b\u0e34\u0e23\u0e31\u0e13\u0e22\u0e4c\u0e21\u0e13\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-09 1000000 47723 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 633\/216  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004411\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e19\u0e34\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004411 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e19\u0e34\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e2a\u0e37\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e15\u0e32\u0e21 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e2b\u0e19\u0e35\u0e49 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e23\u0e38\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 121\/570  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004420\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e19 \u0e04\u0e2d\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"08103\",\"industry_category\":\"\u9271\u696d\u30fb\u63a1\u77f3\",\"industry_label\":\"08103\uff5c\u9271\u696d\u30fb\u63a1\u77f3\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004420 \u0e1a\u0e08.\u0e1f\u0e34\u0e19 \u0e04\u0e2d\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 08103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e39\u0e14\u0e17\u0e23\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e23\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u9271\u696d\u30fb\u63a1\u77f3 75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004438\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47214\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47214\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004438 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 391  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004446\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32\u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004446 \u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e32\u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21  \u0e2a\u0e1a\u0e39\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001525\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001525 \u0e2b\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-09 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001533\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e21\u0e32\u0e01\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001533 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e21\u0e32\u0e01 2569-07-09 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569001951\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e34\u0e49\u0e19\u0e21\u0e39\u0e48 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001951 \u0e1a\u0e08.\u0e40\u0e08\u0e34\u0e49\u0e19\u0e21\u0e39\u0e48 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e2d\u0e42\u0e23\u0e21\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 222  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e22\u0e32\u0e07\u0e42\u0e17\u0e19 11 \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569001969\",\"name_th\":\"\u0e1a\u0e08.\u0e1e.\u0e41\u0e1e\u0e23\u0e23\u0e35\u0e48 \u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01121\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01121\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001969 \u0e1a\u0e08.\u0e1e.\u0e41\u0e1e\u0e23\u0e23\u0e35\u0e48 \u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 01121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e49\u0e19\u0e01\u0e25\u0e49\u0e32\u0e15\u0e49\u0e19\u0e02\u0e49\u0e32\u0e27\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u8fb2\u6797\u6c34\u7523 53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569001977\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e1e\u0e32\u0e30\u0e01\u0e25\u0e49\u0e32\u0e2a\u0e38\u0e01\u0e31\u0e0d\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01121\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01121\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001977 \u0e1a\u0e08.\u0e41\u0e1b\u0e25\u0e07\u0e40\u0e1e\u0e32\u0e30\u0e01\u0e25\u0e49\u0e32\u0e2a\u0e38\u0e01\u0e31\u0e0d\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 01121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e49\u0e19\u0e01\u0e25\u0e49\u0e32\u0e15\u0e49\u0e19\u0e02\u0e49\u0e32\u0e27\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u8fb2\u6797\u6c34\u7523 71\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0615569000521\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000521 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e48\u0e2d\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e17\u0e48\u0e2d\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e44\u0e2d\u0e19\u0e49\u0e33  \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e1c\u0e32\u0e44\u0e2b\u0e21\u0e49 \u88fd\u9020 40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0615569000539\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e48\u0e33\u0e0b\u0e33 289 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000539 \u0e1a\u0e08.\u0e25\u0e48\u0e33\u0e0b\u0e33 289 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d, \u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e31\u0e1a\u0e0b\u0e34\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07, \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e2a\u0e48\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52\/4  \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e0a\u0e49\u0e32\u0e07 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0615569000547\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e23\u0e27\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000547 \u0e1a\u0e08.\u0e41\u0e1e\u0e23\u0e27\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u4e0d\u52d5\u7523 2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0623569000707\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2b\u0e21\u0e23\u0e31\u0e28\u0e21\u0e34\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000707 \u0e2b\u0e08.\u0e40\u0e2b\u0e21\u0e23\u0e31\u0e28\u0e21\u0e34\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 212\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0625569000768\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e2b\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01136\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01136\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000768 \u0e1a\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e2b\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 01136 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1e\u0e32\u0e30\u0e40\u0e2b\u0e47\u0e14\u0e2a\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u8fb2\u6797\u6c34\u7523 212  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0633569000677\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35.\u0e0b\u0e35.\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c999\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000677 \u0e2b\u0e08.\u0e1e\u0e35.\u0e0b\u0e35.\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c999 2569-07-09 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e14\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e14\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 599\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002183\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e2d\u0e30\u0e01\u0e23\u0e35\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002183 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e2d\u0e30\u0e01\u0e23\u0e35\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002205\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e18\u0e32\u0e23\u0e32 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002205 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e18\u0e32\u0e23\u0e32 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\u0e19\u0e49\u0e33\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33  \u0e07\u0e32\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e1c\u0e34\u0e27\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e19\u0e49\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1319\/27  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e44\u0e15\u0e23\u0e42\u0e25\u0e01\u0e19\u0e32\u0e23\u0e162 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0665569000695\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e31\u0e15\u0e16\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000695 \u0e1a\u0e08.\u0e18\u0e19\u0e31\u0e15\u0e16\u0e18\u0e23\u0e23\u0e21 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 296\/5  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e38\u0e21\u0e0a\u0e19 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0675569001471\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e23\u0e32\u0e18\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001471 \u0e1a\u0e08.\u0e18\u0e23\u0e32\u0e18\u0e23\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 289  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003103\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003103 \u0e1a\u0e08.\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 73  \u0e16\u0e19\u0e19\u0e17\u0e23\u0e07\u0e1e\u0e25 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003111\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49 \u0e1a\u0e34\u0e0b\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003111 \u0e1a\u0e08.\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49 \u0e1a\u0e34\u0e0b\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 65  \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e18\u0e32\u0e23\u0e32\u0e21 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002549\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e44\u0e23\u0e2a\u0e4c \u0e0a\u0e32\u0e22\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002549 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e44\u0e23\u0e2a\u0e4c \u0e0a\u0e32\u0e22\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002565\",\"name_th\":\"\u0e1a\u0e08. \u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002565 \u0e1a\u0e08. \u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46900 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000625\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000625 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-09 1000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006960\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006960 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 72101 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34  \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e0a\u0e34\u0e07 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e20\u0e39\u0e21\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c (gis) \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e23\u0e30\u0e22\u0e30\u0e44\u0e01\u0e25 (remote sensing) \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07  \u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 (iee, eia, ehia, sea) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e04\u0e48\u0e32\u0e22\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23  \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32  \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 47\/570  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006978\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006978 \u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u4e0d\u52d5\u7523 58\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0743569000951\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e27\u0e21\u0e17\u0e30\u0e40\u0e25\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000951 \u0e2b\u0e08.\u0e23\u0e27\u0e21\u0e17\u0e30\u0e40\u0e25 2569-07-09 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 135\/182  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0743569000960\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e01\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000960 \u0e2b\u0e08.\u0e17\u0e30\u0e40\u0e25\u0e01\u0e39\u0e49\u0e14 2569-07-09 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 73\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007184\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46442\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46442\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007184 \u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46442 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e19\u0e27\u0e14 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e42\u0e23\u0e21\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/1564  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007222\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007222 \u0e1a\u0e08.\u0e41\u0e2a\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 34\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0753569000081\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e30\u0e04\u0e27\u0e32 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0753569000081 \u0e2b\u0e08.\u0e2d\u0e30\u0e04\u0e27\u0e32 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 2569-07-09 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0765569001453\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e47\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c\u0e23\u0e34\u0e0b\u0e36\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001453 \u0e1a\u0e08.\u0e40\u0e1a\u0e47\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e17\u0e31\u0e27\u0e23\u0e4c\u0e23\u0e34\u0e0b\u0e36\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 45\/184  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0773569000391\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e01\u0e38\u0e22\u0e1a\u0e38\u0e23\u0e35\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0773569000391 \u0e2b\u0e08.\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e01\u0e38\u0e22\u0e1a\u0e38\u0e23\u0e35 2569-07-09 1000000 71202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 915  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0775569002921\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e21\u0e2b\u0e32\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002921 \u0e1a\u0e08.\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e21\u0e2b\u0e32\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04  \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0803569000934\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e25\u0e34\u0e49\u0e21 2555\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000934 \u0e2b\u0e08.\u0e40\u0e04\u0e25\u0e34\u0e49\u0e21 2555 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c  \u0e0a\u0e32  \u0e01\u0e32\u0e41\u0e1f \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e04\u0e38\u0e01\u0e01\u0e35\u0e49 \u0e1e\u0e34\u0e0b\u0e0b\u0e48\u0e32 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 207\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002629\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e23\u0e34\u0e0a \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c 789  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002629 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e23\u0e34\u0e0a \u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e2a\u0e4c 789  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e1a\u0e01\u0e25\u0e34\u0e48\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 188\/19  \u0e16\u0e19\u0e19\u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07-\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002637\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e38\u0e02\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1b\u0e32\u0e25\u0e34\u0e19 \u0e42\u0e0a\u0e04\u0e2d\u0e25\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002637 \u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e38\u0e02\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1b\u0e32\u0e25\u0e34\u0e19 \u0e42\u0e0a\u0e04\u0e2d\u0e25\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46632 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e44\u0e21\u0e49\u0e17\u0e48\u0e2d\u0e19 \u0e44\u0e21\u0e49\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e48\u0e2d\u0e19 \u0e41\u0e1c\u0e48\u0e19 \u0e41\u0e16\u0e1a \u0e40\u0e2a\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e28\u0e29\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e2b\u0e21\u0e32\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e0a\u0e35\u0e27\u0e21\u0e27\u0e25 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e1e\u0e25\u0e2d\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22(\u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e01\u0e25\u0e1a \u0e0a\u0e32\u0e19\u0e2d\u0e49\u0e2d\u0e22 \u0e1f\u0e32\u0e07\u0e02\u0e49\u0e32\u0e27 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e1c\u0e31\u0e01\u0e15\u0e1a\u0e0a\u0e27\u0e32 \u0e0b\u0e31\u0e07\u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e01\u0e30\u0e25\u0e32 \u0e21\u0e39\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e08\u0e32\u0e01\u0e0a\u0e38\u0e21\u0e0a\u0e19)\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e4a\u0e32\u0e0b\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e39\u0e19 \u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569012659\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e25 \u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012659 \u0e1a\u0e08.\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e25 \u0e42\u0e0b\u0e25\u0e48\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e01\u0e23\u0e34\u0e14 \u0e2d\u0e2d\u0e1f\u0e01\u0e23\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 19\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012667\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 \u0e28\u0e34\u0e25\u0e32\u0e17\u0e23\u0e32\u0e22\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012667 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 \u0e28\u0e34\u0e25\u0e32\u0e17\u0e23\u0e32\u0e22\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e48\u0e2d\u0e17\u0e23\u0e32\u0e22 \u0e14\u0e39\u0e14\u0e17\u0e23\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 177\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012683\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012683 \u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 46\/110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012691\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e28\u0e34\u0e27\u0e32\u0e23\u0e31\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012691 \u0e1a\u0e08.\u0e28\u0e28\u0e34\u0e27\u0e32\u0e23\u0e31\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 10\/40-41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012705\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e48\u0e32 \u0e1e\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81292\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81292\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012705 \u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e48\u0e32 \u0e1e\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 81292 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 27\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e30\u0e29\u0e31\u0e15\u0e23\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012730\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e34\u0e0a\u0e0d\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012730 \u0e1a\u0e08.\u0e13\u0e34\u0e0a\u0e0d\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e4d\u0e32\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 63\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012748\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e27\u0e07\u0e40\u0e2d\u0e4b \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012748 \u0e1a\u0e08.\u0e2b\u0e25\u0e27\u0e07\u0e40\u0e2d\u0e4b \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 50\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012756\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e21\u0e32\u0e22\u0e14\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012756 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e21\u0e32\u0e22\u0e14\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e42\u0e15\u0e4a\u0e30 \u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e32\u0e19\u0e0a\u0e32\u0e21 \u0e0a\u0e49\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e27\u0e17\u0e35 \u0e09\u0e32\u0e01 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 131\/138  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012772\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e17\u0e23\u0e35 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012772 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e17\u0e23\u0e35 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 33\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012799\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e29\u0e13\u0e38\u0e1e\u0e07\u0e28\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012799 \u0e1a\u0e08.\u0e0a\u0e34\u0e29\u0e13\u0e38\u0e1e\u0e07\u0e28\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e31\u0e01 \u0e2d\u0e1a \u0e23\u0e35\u0e14 \u5efa\u8a2d 218\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010192\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e04\u0e41\u0e04\u0e23\u0e4c\u0e23\u0e2d\u0e25\u0e25\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010192 \u0e1a\u0e08.\u0e41\u0e21\u0e04\u0e41\u0e04\u0e23\u0e4c\u0e23\u0e2d\u0e25\u0e25\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e19\u0e2d\u0e01\u0e23\u0e49\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 142\/58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0855569000511\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e38\u0e4b\u0e21\u0e40\u0e1f\u0e23\u0e0a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000511 \u0e1a\u0e08.\u0e08\u0e38\u0e4b\u0e21\u0e40\u0e1f\u0e23\u0e0a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46900 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/1  \u0e16\u0e19\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0855569000529\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22 \u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000529 \u0e1a\u0e08.\u0e23\u0e27\u0e22 \u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c  \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200\/3  \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0865569001193\",\"name_th\":\"\u0e1a\u0e08.  \u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e0a \u0e0a\u0e38\u0e21\u0e1e\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001193 \u0e1a\u0e08.  \u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e0a \u0e0a\u0e38\u0e21\u0e1e\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47630 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569005490\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e48\u0e2d\u0e15\u0e49\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005490 \u0e1a\u0e08.\u0e40\u0e17\u0e48\u0e2d\u0e15\u0e49\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005503\",\"name_th\":\"\u0e1a\u0e08.123 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66210\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66210\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005503 \u0e1a\u0e08.123 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 66210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 26\/254  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005511\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e25\u0e34\u0e19\u0e14\u0e32 \u0e1a\u0e34\u0e49\u0e27\u0e15\u0e35\u0e49 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005511 \u0e1a\u0e08.\u0e2d\u0e25\u0e34\u0e19\u0e14\u0e32 \u0e1a\u0e34\u0e49\u0e27\u0e15\u0e35\u0e49 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 444\/901  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005520\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 6354 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005520 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 6354 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e01\u0e38\u0e49\u0e07 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07-\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e01\u0e38\u0e49\u0e07 \u0e1b\u0e25\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120\/158  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005538\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e25\u0e32\u0e25\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005538 \u0e1a\u0e08.\u0e1f\u0e23\u0e38\u0e4a\u0e15\u0e25\u0e32\u0e25\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e04\u0e32\u0e40\u0e1f\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 21  \u0e0b\u0e2d\u0e22 \u0e02\u0e33\u0e2d\u0e38\u0e17\u0e34\u0e284 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005546\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e1959 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005546 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e1959 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 59  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e04\u0e23\u0e21\u0e07\u0e04\u0e25 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005554\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e19\u0e1a\u0e38\u0e15\u0e23 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005554 \u0e1a\u0e08.\u0e0a\u0e34\u0e19\u0e1a\u0e38\u0e15\u0e23 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 (\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e07\u0e32\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e01\u0e25\u0e36\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 2  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e0b\u0e2d\u0e2249 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005562\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e44\u0e19\u0e19\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005562 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e44\u0e19\u0e19\u0e4c\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005597\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e32 \u0e27\u0e2d\u0e25\u0e15\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005597 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e32 \u0e27\u0e2d\u0e25\u0e15\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 188\/2  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07 \u0e23.5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0933569000305\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e23\u0e35\u0e19\u0e32\u0e04\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0933569000305 \u0e2b\u0e08.\u0e28\u0e23\u0e35\u0e19\u0e32\u0e04\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-09 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0935569000811\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e23\u0e21\u0e1b\u0e23\u0e34\u0e21 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000811 \u0e1a\u0e08.\u0e40\u0e1b\u0e23\u0e21\u0e1b\u0e23\u0e34\u0e21 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 7\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0945569000692\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e19\u0e23\u0e31\u0e01 \u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47214\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47214\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000692 \u0e1a\u0e08.\u0e14\u0e2d\u0e19\u0e23\u0e31\u0e01 \u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 47214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0945569000706\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e1f \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000706 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e1f \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 10120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 116  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0955569000561\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000561 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 7  \u0e0b\u0e2d\u0e22 8(\u0e1c\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e074) \u0e16\u0e19\u0e19\u0e1c\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e074 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007048\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e17\u0e22\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007048 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e19\u0e44\u0e17\u0e22\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a 2569-07-08 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e19\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 99005 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 2 \u0e0b\u0e2d\u0e22 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007064\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0a\u0e31\u0e22\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007064 \u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e0a\u0e31\u0e22\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-08 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 345\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007072\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007072 \u0e2b\u0e08.\u0e27\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-08 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/152  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c111 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007081\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007081 \u0e2b\u0e08.\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-08 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/52  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 85 \u0e41\u0e22\u0e01 2-5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007099\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e31\u0e1e\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007099 \u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e31\u0e1e\u0e1f\u0e32\u0e21 2569-07-08 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/52  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 85 \u0e41\u0e22\u0e01 2-5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007102\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e23\u0e35\u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007102 \u0e2b\u0e08.\u0e27\u0e32\u0e23\u0e35\u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c 2569-07-08 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 345\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007111\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007111 \u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 2569-07-08 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/152  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c111 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007129\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1f\u0e32\u0e21 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007129 \u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1f\u0e32\u0e21 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d 2569-07-08 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/342  \u0e0b\u0e2d\u0e22 \u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e3420 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007137\",\"name_th\":\"\u0e2b\u0e08.99 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007137 \u0e2b\u0e08.99 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d 2569-07-08 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/342  \u0e0b\u0e2d\u0e22 \u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e3420 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007145\",\"name_th\":\"\u0e2b\u0e08.88 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007145 \u0e2b\u0e08.88 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d 2569-07-08 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 345\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007153\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007153 \u0e2b\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25\u0e44\u0e17\u0e22 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-08 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 212 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1721(\u0e2d\u0e42\u0e28\u0e01) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007161\",\"name_th\":\"\u0e2b\u0e08.9 \u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007161 \u0e2b\u0e08.9 \u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-08 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 42\/36  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e21.\u0e18\u0e19\u0e32\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007170\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01271\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01271\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007170 \u0e2b\u0e08.\u0e40\u0e08\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-08 1000000 01271 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 30\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007188\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 99 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007188 \u0e2b\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 99 \u0e44\u0e17\u0e22\u0e40\u0e04\u0e21\u0e35\u0e04\u0e25\u0e2d 2569-07-08 1000000 20121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u88fd\u9020 30\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007200\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e41\u0e2a\u0e07\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21002\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21002\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007200 \u0e2b\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e41\u0e2a\u0e07\u0e44\u0e17\u0e22 2569-07-08 1000000 21002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e2a\u0e01\u0e31\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e01\u0e31\u0e0d\u0e0a\u0e32\u0e41\u0e25\u0e30\u0e01\u0e31\u0e0d\u0e0a\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07 \u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e21 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e01\u0e31\u0e0d \u0e0a\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e32\u0e23\u0e41\u0e04\u0e19\u0e19\u0e32\u0e1a\u0e34\u0e44\u0e14\u0e2d\u0e2d\u0e25 (cbd) \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e32\u0e23\u0e40\u0e15\u0e15\u0e23\u0e32\u0e44\u0e2e\u0e42\u0e14\u0e23\u0e41\u0e04\u0e19\u0e19\u0e32\u0e1a\u0e34\u0e19\u0e2d\u0e25 (thc) \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35 \u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13 thc \u0e40\u0e01\u0e34\u0e19\u0e23\u0e49\u0e2d\u0e22\u0e25\u0e30 0.2 \u0e42\u0e14\u0e22\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e22\u0e32\u0e40\u0e2a\u0e1e\u0e15\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e22\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 26  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128548\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128548 \u0e1a\u0e08.\u0e1f\u0e34\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e15\u0e2d\u0e25\u0e14\u0e08\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u88fd\u9020 85\/28  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 79 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128572\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128572 \u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 99\/390  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e2a\u0e32\u0e17\u0e23-\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19 2 \u0e0b\u0e2d\u0e22 \u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128581\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e19\u0e40\u0e0b\u0e34\u0e07 \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"61900\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"61900\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128581 \u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e19\u0e40\u0e0b\u0e34\u0e07 \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e27\u0e19\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 61900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23          \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 65\/75  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e40\u0e1e\u0e25\u0e2a1 \u0e0b\u0e2d\u0e22 14 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128599\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79909\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79909\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128599 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 79909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 114  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e20\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128602\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e31\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128602 \u0e1a\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e31\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 64202 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u91d1\u878d\u30fb\u4fdd\u967a 19\/43  \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e1a\u0e32\u0e07\u0e1a\u0e31\u0e27 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128611\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e41\u0e15\u0e19\u0e14\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e2d\u0e1a\u0e35\u0e40\u0e2d\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128611 \u0e1a\u0e08.\u0e2a\u0e41\u0e15\u0e19\u0e14\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e2d\u0e1a\u0e35\u0e40\u0e2d\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 134  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 40 \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128629\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128629 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e0b\u0e35\u0e0b\u0e31\u0e48\u0e19 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 999\/9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e34 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e40\u0e28\u0e2a \u0e41\u0e2d\u0e17 \u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2408-2410 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 24 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128637\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e08\u0e34\u0e19\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46492\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46492\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128637 \u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e08\u0e34\u0e19\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 319  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e15\u0e38\u0e23\u0e31\u0e2a\u0e08\u0e32\u0e21\u0e08\u0e38\u0e23\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 24 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128653\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e21 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e17 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128653 \u0e1a\u0e08.\u0e41\u0e04\u0e1b\u0e0b\u0e39\u0e21 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e17 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 146\/16  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e21\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128670\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e42\u0e15\u0e23\u0e32 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128670 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e42\u0e15\u0e23\u0e32 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e2245 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128700\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e14\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128700 \u0e1a\u0e08.\u0e0b\u0e35\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e14\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1e\u0e37\u0e0a\u0e1c\u0e25  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/1  \u0e0b\u0e2d\u0e22 \u0e2b\u0e19\u0e2d\u0e07\u0e23\u0e30\u0e41\u0e2b\u0e07 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128742\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128742 \u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 264\/204  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 19 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128751\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128751 \u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar) \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u91d1\u878d\u30fb\u4fdd\u967a 33\/36  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e2d\u0e25\u0e25\u0e4c\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128769\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128769 \u0e1a\u0e08.\u0e40\u0e04 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e23\u0e27\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u533b\u7642\u30fb\u798f\u7949 236\/6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e23\u0e0b\u0e34\u0e42\u0e2d \u0e42\u0e2e\u0e21 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 110 \u0e21.\u0e40\u0e23\u0e0b\u0e34\u0e42\u0e2d \u0e42\u0e2e\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128777\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128777 \u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5efa\u8a2d 17\/6  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 72 \u0e41\u0e22\u0e01 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128785\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e19\u0e4c\u0e19\u0e34\u0e2a\u0e15\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128785 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e19\u0e4c\u0e19\u0e34\u0e2a\u0e15\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e34\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22 \u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1991\/180  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128807\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35\u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128807 \u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35\u0e1e\u0e35 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28\/77  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 54 \u0e41\u0e22\u0e01 4-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128815\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e49\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128815 \u0e1a\u0e08.\u0e02\u0e49\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e08\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 161  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128831\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e49\u0e0b\u0e48\u0e32 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128831 \u0e1a\u0e08.\u0e40\u0e01\u0e49\u0e0b\u0e48\u0e32 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e20 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 321   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 01 \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d 25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128840\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e38\u0e19\u0e19\u0e34\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128840 \u0e1a\u0e08.\u0e17\u0e38\u0e19\u0e19\u0e34\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 70202 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 68\/3  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 43 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128858\",\"name_th\":\"\u0e1a\u0e08.\u0e0d\u0e32\u0e13\u0e34\u0e01\u0e32 \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128858 \u0e1a\u0e08.\u0e0d\u0e32\u0e13\u0e34\u0e01\u0e32 \u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e0a\u0e23 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 119  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e35\u0e44\u0e2d\u0e40\u0e2d\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4f12 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e21\u0e40\u0e2b\u0e2a\u0e31\u0e01\u0e02\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128874\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128874 \u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e14\u0e47\u0e19\u0e17\u0e31\u0e25\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e15\u0e23\u0e27\u0e08 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e1f\u0e31\u0e19 \u0e42\u0e23\u0e04\u0e40\u0e2b\u0e07\u0e37\u0e2d\u0e01 \u0e42\u0e23\u0e04\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e17\u0e31\u0e19\u0e15\u0e23\u0e23\u0e21 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u533b\u7642\u30fb\u798f\u7949 34\/58,34\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e0b\u0e2d\u0e2214 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128904\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e31\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128904 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e31\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 905\/1  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128921\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e04\u0e34\u0e14 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e41\u0e17\u0e25\u0e25\u0e34\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128921 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e04\u0e34\u0e14 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e41\u0e17\u0e25\u0e25\u0e34\u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07  \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e14 \u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 99\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e35\u0e40\u0e08\u0e0b\u0e35 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e41\u0e2a\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c - \u0e23\u0e39\u0e40\u0e1a\u0e35\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128947\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e2a\u0e15\u0e49\u0e32 \u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e49\u0e04\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31009\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31009\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128947 \u0e1a\u0e08.\u0e40\u0e19\u0e2a\u0e15\u0e49\u0e32 \u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e49\u0e04\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 31009 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1a\u0e34\u0e49\u0e27\u0e2d\u0e34\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u88fd\u9020 428\/118  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128955\",\"name_th\":\"\u0e1a\u0e08.\u0e13 \u0e02\u0e13\u0e30 \u0e1f\u0e39\u0e49\u0e14\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10752\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10752\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128955 \u0e1a\u0e08.\u0e13 \u0e02\u0e13\u0e30 \u0e1f\u0e39\u0e49\u0e14\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 10752 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e4d\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 118\/3  \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128963\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e14\u0e35\u0e40\u0e2d\u0e1f \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128963 \u0e1a\u0e08.\u0e0b\u0e35\u0e14\u0e35\u0e40\u0e2d\u0e1f \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/99  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1954\/1 \u0e41\u0e22\u0e016-12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128980\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39 \u0e19\u0e2d\u0e17\u0e18\u0e34\u0e07 \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128980 \u0e1a\u0e08.\u0e14\u0e39 \u0e19\u0e2d\u0e17\u0e18\u0e34\u0e07 \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0a\u0e32 \u0e0a\u0e32\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e0a\u0e32\u0e21\u0e31\u0e17\u0e09\u0e30 \u0e0a\u0e32\u0e1c\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 699\/4  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e32\u0e0b\u0e48\u0e32 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e22 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128998\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08\u0e1a\u0e35 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128998 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08\u0e1a\u0e35 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 498\/304  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129005\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e21\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129005 \u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e21\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e40\u0e1e\u0e28 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3-34 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 66\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129013\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e43\u0e08 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129013 \u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e43\u0e08 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e27\u0e0a \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 659\/186  \u0e16\u0e19\u0e19\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129021\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129021 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/648  \u0e0b\u0e2d\u0e22 \u0e19\u0e34\u0e21\u0e34\u0e15\u0e23\u0e43\u0e2b\u0e21\u0e48 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129048\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e0d\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129048 \u0e1a\u0e08.\u0e0a\u0e0d\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 17 \u0e41\u0e22\u0e01 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129056\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e41\u0e1e\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129056 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e41\u0e1e\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/42  \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129064\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e19\u0e15\u0e17\u0e34\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129064 \u0e1a\u0e08.\u0e41\u0e19\u0e15\u0e17\u0e34\u0e22\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 36\/93  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e01\u0e49\u0e32\u0e41\u0e2a\u0e19\u0e2b\u0e49\u0e32 \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 23 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129081\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19\u0e04\u0e35\u0e22\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129081 \u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19\u0e04\u0e35\u0e22\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289\/44  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 6\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129137\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e35\u0e2a\u0e4c \u0e41\u0e2d\u0e47\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66221\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66221\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129137 \u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e35\u0e2a\u0e4c \u0e41\u0e2d\u0e47\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 66221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e2d\u0e1a\u0e23\u0e21 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u91d1\u878d\u30fb\u4fdd\u967a 2  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 79 \u0e41\u0e22\u0e01 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129153\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e42\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10752\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10752\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129153 \u0e1a\u0e08.\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e42\u0e0b\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 10752 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e49\u0e32\u0e27\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u88fd\u9020 973  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e23\u0e2a\u0e34\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 10l \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129188\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e09\u0e32\u0e22\u0e41\u0e2a\u0e07 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129188 \u0e1a\u0e08.\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e09\u0e32\u0e22\u0e41\u0e2a\u0e07 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 94  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e2a\u0e38\u0e02\u0e43\u0e08 12 \u0e16\u0e19\u0e19\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129200\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e35789 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129200 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e35789 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e34\u0e28\u0e32\u0e25-\u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 30 \u0e41\u0e22\u0e01 8-8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129218\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e1c\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10302\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10302\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129218 \u0e1a\u0e08.\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e1c\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 10302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 106  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e27\u0e35\u0e22\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129293\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e04\u0e25\u0e2d\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129293 \u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e04\u0e25\u0e2d\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (marketplace platform) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 300\/218  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 6\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129331\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129331 \u0e1a\u0e08.\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 38\/280  \u0e0b\u0e2d\u0e22 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e27\u0e34\u0e08\u0e31\u0e22 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129358\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e30\u0e21\u0e38\u0e19 \u0e41\u0e1a\u0e47\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129358 \u0e1a\u0e08.\u0e25\u0e30\u0e21\u0e38\u0e19 \u0e41\u0e1a\u0e47\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e16\u0e37\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e42\u0e14\u0e22\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105\/12  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129374\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e21\u0e04\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129374 \u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e21\u0e04\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 18112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 35  \u0e0b\u0e2d\u0e22 \u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129404\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e35 \u0e2d\u0e30\u0e1a\u0e31\u0e19\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129404 \u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e35 \u0e2d\u0e30\u0e1a\u0e31\u0e19\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 69200 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 406\/31  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002267\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e01 \u0e42\u0e1b\u0e23\u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46433\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46433\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002267 \u0e2b\u0e08.\u0e40\u0e2d\u0e01 \u0e42\u0e1b\u0e23\u0e0a\u0e47\u0e2d\u0e1b 2569-07-08 1000000 46433 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e32 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e07  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 300\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002275\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e01 \u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07 \u0e42\u0e1b\u0e23\u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46433\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46433\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002275 \u0e2b\u0e08.\u0e40\u0e2d\u0e01 \u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07 \u0e42\u0e1b\u0e23\u0e0a\u0e47\u0e2d\u0e1b 2569-07-08 1000000 46433 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e25\u0e32 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e07  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 300\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022529\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e41\u0e04\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022529 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e41\u0e04\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 64202 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 91\/12  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30 \u0e1e\u0e23\u0e35\u0e40\u0e17\u0e35\u0e48\u0e22\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022537\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e23\u0e2b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022537 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e23\u0e2b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 82\/104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022553\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35.\u0e27\u0e23\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46316\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46316\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022553 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35.\u0e27\u0e23\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46316 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48\u0e2a\u0e14 \u0e44\u0e02\u0e48\u0e40\u0e1b\u0e47\u0e14 \u0e44\u0e02\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e44\u0e02\u0e48\u0e40\u0e04\u0e47\u0e21 \u0e44\u0e02\u0e48\u0e40\u0e22\u0e35\u0e48\u0e22\u0e27\u0e21\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e44\u0e02\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 362  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022588\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e17\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022588 \u0e1a\u0e08.\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e17\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 333\/47  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e01\u0e21.5 - \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022596\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022596 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 557\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022626\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e19\u0e21\u0e08\u0e35\u0e19\u0e19\u0e49\u0e2d\u0e21\u0e08\u0e34\u0e15\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10752\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10752\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022626 \u0e1a\u0e08.\u0e02\u0e19\u0e21\u0e08\u0e35\u0e19\u0e19\u0e49\u0e2d\u0e21\u0e08\u0e34\u0e15\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 10752 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1b\u0e23\u0e38\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a  \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 61\/198  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c24 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022642\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e2d\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022642 \u0e1a\u0e08.\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e2d\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 11043 \u0e1c\u0e25\u0e34\u0e15\u0e02\u0e19\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 5\/96  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e41\u0e1a\u0e23\u0e34\u0e48\u0e07 58 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 107 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022651\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e2d\u0e40\u0e1a\u0e34\u0e25 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022651 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e40\u0e2d\u0e40\u0e1a\u0e34\u0e25 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e15\u0e31\u0e27\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e49\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 987\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022669\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e25\u0e17\u0e23\u0e2d\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022669 \u0e1a\u0e08.\u0e27\u0e32\u0e25\u0e17\u0e23\u0e2d\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e23\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e40\u0e17\u0e1e\u0e37\u0e49\u0e19 \u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5efa\u8a2d 212  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025536\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025536 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 165\/48  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e1a\u0e14\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025544\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e35\u0e42\u0e27 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e42\u0e01\u0e23\u0e27\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025544 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e35\u0e42\u0e27 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e42\u0e01\u0e23\u0e27\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 (exhibition) \u0e07\u0e32\u0e19\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (event planner) \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 39\/1067  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10132\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10132\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025561 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 10132 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19 \u0e2b\u0e21\u0e39\u0e22\u0e2d \u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e44\u0e2a\u0e49\u0e01\u0e23\u0e2d\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e07\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 20\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025579\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e2a.\u0e14\u0e35.\u0e40\u0e17\u0e042018 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025579 \u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e2a.\u0e14\u0e35.\u0e40\u0e17\u0e042018 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 (network) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 80\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025587\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025587 \u0e1a\u0e08.\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 145\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025609\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e1f\u0e40\u0e04 \u0e0b\u0e35\u0e19\u0e34\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025609 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e1f\u0e40\u0e04 \u0e0b\u0e35\u0e19\u0e34\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 1\/160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025617\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025617 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 42\/92  \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025633\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025633 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u5efa\u8a2d 89\/138  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025641\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e21\u0e32\u0e28 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025641 \u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e21\u0e32\u0e28 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46441 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/68  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002275\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e0a \u0e17\u0e35 \u0e0b\u0e35\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002275 \u0e2b\u0e08.\u0e40\u0e2d\u0e0a \u0e17\u0e35 \u0e0b\u0e35\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 2569-07-08 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 46\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002283\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e27\u0e2d\u0e15\u0e0b\u0e4c \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002283 \u0e2b\u0e08.\u0e04\u0e27\u0e2d\u0e15\u0e0b\u0e4c \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-08 1000000 11041 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 89\/16  \u0e16\u0e19\u0e19\u0e1b\u0e17\u0e38\u0e21\u0e25\u0e32\u0e14\u0e2b\u0e25\u0e38\u0e21\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020968\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e22\u0e14\u0e4c\u0e42\u0e17\u0e40\u0e1b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020968 \u0e1a\u0e08.\u0e2a\u0e21\u0e32\u0e22\u0e14\u0e4c\u0e42\u0e17\u0e40\u0e1b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 86203 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e21\u0e35\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u533b\u7642\u30fb\u798f\u7949 145\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e31\u0e22\u0e44\u0e1e\u0e23\u0e34\u0e19\u0e28\u0e34\u0e23\u0e34 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e21 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020984\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e21\u0e48\u0e32 \u0e42\u0e1b\u0e23 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28160\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28160\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020984 \u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e21\u0e48\u0e32 \u0e42\u0e1b\u0e23 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 28160 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07 \u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u88fd\u9020 20\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020992\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e34\u0e2a \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020992 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e34\u0e2a \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e42\u0e2a\u0e15\u0e17\u0e31\u0e28\u0e19\u0e39\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021018\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e38\u0e17\u0e18\u0e34\u0e27\u0e07\u0e28\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021018 \u0e1a\u0e08.\u0e1e\u0e38\u0e17\u0e18\u0e34\u0e27\u0e07\u0e28\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021026\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e2d \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021026 \u0e1a\u0e08.\u0e1e\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e2d \u0e42\u0e2e\u0e25\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021034\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32\u0e42\u0e04\u0e40\u0e14\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021034 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32\u0e42\u0e04\u0e40\u0e14\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 28299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 222\/223  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021042\",\"name_th\":\"\u0e1a\u0e08.79 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021042 \u0e1a\u0e08.79 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u5efa\u8a2d 92\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021051\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021051 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 66\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021069\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e04\u0e27\u0e2d\u0e25\u0e40\u0e21\u0e14 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021069 \u0e1a\u0e08.\u0e2d\u0e35\u0e04\u0e27\u0e2d\u0e25\u0e40\u0e21\u0e14 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/291  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021077\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e14\u0e21\u0e0a\u0e31\u0e22 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021077 \u0e1a\u0e08.\u0e2d\u0e38\u0e14\u0e21\u0e0a\u0e31\u0e22 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 225\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e351 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021107\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28240\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28240\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021107 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 28240 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e25\u0e35\u0e1f\u0e15\u0e4c \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e25\u0e34\u0e1f\u0e15\u0e4c \u0e1a\u0e31\u0e19\u0e44\u0e14\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01-\u0e43\u0e2b\u0e0d\u0e48 \u0e25\u0e34\u0e1f\u0e15\u0e4c\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 98\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021115\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e25\u0e39\u0e40\u0e17\u0e04 \u0e01\u0e25\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021115 \u0e1a\u0e08.\u0e2d\u0e25\u0e39\u0e40\u0e17\u0e04 \u0e01\u0e25\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2d\u0e25\u0e38\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 45\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004440\",\"name_th\":\"\u0e1a\u0e08.555 \u0e04\u0e32\u0e23\u0e4c\u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0145569004440 \u0e1a\u0e08.555 \u0e04\u0e32\u0e23\u0e4c\u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e25\u0e49\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001530\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e01\u0e1a\u0e38\u0e4a\u0e04 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001530 \u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e01\u0e1a\u0e38\u0e4a\u0e04 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 25  \u0e16\u0e19\u0e19\u0e2a\u0e35\u0e14\u0e32 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001548\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001548 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e1a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e34\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002498\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e42\u0e22\u0e18\u0e32 1972 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002498 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e42\u0e22\u0e18\u0e32 1972 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 49\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002851\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15\u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58114\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58114\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002851 \u0e2b\u0e08.\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e32\u0e23\u0e4c\u0e15\u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e4c 2569-07-08 1000000 58114 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e49\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 120\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002860\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e17\u0e2d\u0e07 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2026\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002860 \u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e17\u0e2d\u0e07 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2026 2569-07-08 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e42\u0e14\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e1a\u0e31\u0e2a \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 58\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002886\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e27\u0e42\u0e25\u0e21\u0e39\u0e1f \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002886 \u0e2b\u0e08.\u0e40\u0e27\u0e42\u0e25\u0e21\u0e39\u0e1f \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-08 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23  \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f \u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e23\u0e21\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002894\",\"name_th\":\"\u0e2b\u0e08. \u0e23\u0e31\u0e0a \u0e21\u0e39\u0e1f\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002894 \u0e2b\u0e08. \u0e23\u0e31\u0e0a \u0e21\u0e39\u0e1f 2569-07-08 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22  \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f \u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e23\u0e21\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d  \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002908\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35\u0e40\u0e27\u0e25 \u0e40\u0e27\u0e25\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002908 \u0e2b\u0e08.\u0e14\u0e35\u0e40\u0e27\u0e25 \u0e40\u0e27\u0e25 2569-07-08 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e41\u0e1a\u0e48\u0e07\u0e41\u0e22\u0e01  \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u4e0d\u52d5\u7523 66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035981\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e34\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58192\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58192\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035981 \u0e1a\u0e08.\u0e22\u0e34\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 58192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 3\/96  \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001235\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001235 \u0e2b\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 2569-07-08 1000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e08\u0e31\u0e1a\u0e22\u0e36\u0e14\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e4d\u0e32\u0e41\u0e2b\u0e19\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 788\/6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e18\u0e32\u0e23\u0e32 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0213569001251\",\"name_th\":\"\u0e2b\u0e08.\u0e2e\u0e27\u0e01 \u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001251 \u0e2b\u0e08.\u0e2e\u0e27\u0e01 \u0e04\u0e49\u0e32\u0e02\u0e49\u0e32\u0e27 2569-07-08 1000000 46315 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e21\u0e47\u0e14 \u0e2b\u0e25\u0e32\u0e22\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0213569001260\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001260 \u0e2b\u0e08.\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17 2569-07-08 1000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009092\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49\u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009092 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49\u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e01 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e36\u0e49\u0e19-\u0e25\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e48\u0e2d\u0e19\u0e41\u0e23\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e25\u0e39\u0e01\u0e23\u0e2d\u0e01 \u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e01\u0e23\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e27\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e41\u0e21\u0e48\u0e41\u0e23\u0e07 \u0e40\u0e1f\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e01\u0e17\u0e35\u0e48\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e22\u0e01\u0e02\u0e2d\u0e07 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e22\u0e01(forklift) \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e22\u0e01\u0e41\u0e25\u0e30\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e27\u0e22 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e23\u0e16\u0e2a\u0e32\u0e25\u0e35\u0e48 (\u0e23\u0e16\u0e40\u0e02\u0e47\u0e19\u0e25\u0e49\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e27) \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e01\u0e25 \u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e22\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e22\u0e01\u0e25\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e22\u0e01\u0e41\u0e25\u0e30\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u88fd\u9020 44\/60  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e2d\u0e01\u0e22\u0e32\u0e22\u0e0a\u0e32 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009131\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e25\u0e34\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009131 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e25\u0e34\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47711 ) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e15\u0e23\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 108\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002152\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e0b\u0e35 \u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e1f\u0e23\u0e38\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002152 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e0b\u0e35 \u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e1f\u0e23\u0e38\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e25\u0e49\u0e32\u0e07 \u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0263569000166\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e34\u0e19 \u0e2d\u0e34\u0e2a\u0e21\u0e32\u0e41\u0e2d\u0e25\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0263569000166 \u0e2b\u0e08.\u0e1a\u0e34\u0e19 \u0e2d\u0e34\u0e2a\u0e21\u0e32\u0e41\u0e2d\u0e25 2569-07-08 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u904b\u8f38\u30fb\u7269\u6d41 20\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0265569000770\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d \u0e41\u0e2d\u0e21 \u0e44\u0e2d \u0e41\u0e04\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000770 \u0e1a\u0e08.\u0e44\u0e2d \u0e41\u0e2d\u0e21 \u0e44\u0e2d \u0e41\u0e04\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 20232 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u88fd\u9020 100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0265569000796\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e04\u0e49\u0e33-\u0e17\u0e2d\u0e07\u0e04\u0e39\u0e13 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000796 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e04\u0e49\u0e33-\u0e17\u0e2d\u0e07\u0e04\u0e39\u0e13 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e15\u0e23\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e44\u0e2d\u0e28\u0e04\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e49\u0e01 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e02\u0e19\u0e21\u0e2d\u0e1a\u0e01\u0e23\u0e2d\u0e1a \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e0a\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e1e\u0e34\u0e0a\u0e0b\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e0a\u0e38\u0e14\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e40\u0e1a\u0e23\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 170\/219  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0303569002605\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002605 \u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a 2569-07-08 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e2b\u0e01\u0e25\u0e49\u0e2d  \u0e23\u0e16\u0e2a\u0e34\u0e1a\u0e25\u0e49\u0e2d \u0e23\u0e16\u0e1a\u0e31\u0e19 \u0e21\u0e34\u0e19\u0e34\u0e1a\u0e31\u0e2a \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 999\/119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002613\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e1e\u0e23\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002613 \u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e1e\u0e23\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-08 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e1a\u0e01 \u904b\u8f38\u30fb\u7269\u6d41 96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002621\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e38\u0e11\u0e32\u0e21\u0e32\u0e28 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002621 \u0e2b\u0e08.\u0e08\u0e38\u0e11\u0e32\u0e21\u0e32\u0e28 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-08 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 42\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002656\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e04\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002656 \u0e2b\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e04\u0e34\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 555\/119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569000980\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e19\u0e15\u0e34\u0e19\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569000980 \u0e2b\u0e08.\u0e40\u0e19\u0e15\u0e34\u0e19\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-08 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 216  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0315569001848\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e0a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001848 \u0e1a\u0e08.\u0e42\u0e2d\u0e0a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 56102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 435\/166  \u0e16\u0e19\u0e19\u0e08\u0e34\u0e23\u0e30 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0343569001820\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001820 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 175  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003069\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e42\u0e25\u0e48 \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003069 \u0e1a\u0e08.\u0e40\u0e04\u0e42\u0e25\u0e48 \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e31\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e2a\u0e23\u0e49\u0e2d\u0e22\u0e04\u0e2d \u0e2a\u0e23\u0e49\u0e2d\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e37\u0e2d \u0e15\u0e48\u0e32\u0e07\u0e2b\u0e39 \u0e08\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 293  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 2172 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003077\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e21\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003077 \u0e1a\u0e08.\u0e0b\u0e34\u0e01\u0e21\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d \u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e0a\u0e38\u0e14\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e41\u0e25\u0e30\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 555\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0403569003007\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e31\u0e19\u0e17\u0e19\u0e35\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003007 \u0e2b\u0e08.\u0e28\u0e31\u0e19\u0e17\u0e19\u0e35\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 161  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003015\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e2d\u0e21\u0e22\u0e38\u0e17\u0e18\u0e19\u0e49\u0e2d\u0e22\u0e04\u0e49\u0e32\u0e44\u0e02\u0e48\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003015 \u0e2b\u0e08.\u0e08\u0e2d\u0e21\u0e22\u0e38\u0e17\u0e18\u0e19\u0e49\u0e2d\u0e22\u0e04\u0e49\u0e32\u0e44\u0e02\u0e48 2569-07-08 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e44\u0e02\u0e48\u0e40\u0e1b\u0e47\u0e14 \u0e44\u0e02\u0e48\u0e19\u0e01\u0e01\u0e23\u0e30\u0e17\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e02\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 301  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006491\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04-\u0e42\u0e01 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006491 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04-\u0e42\u0e01 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 322\/19  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e23\u0e2d\u0e22\u0e31\u0e25\u0e23\u0e35\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 5 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006504\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e2a\u0e42\u0e19\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006504 \u0e1a\u0e08.\u0e27\u0e31\u0e2a\u0e42\u0e19\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006512\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e17\u0e35\u0e40\u0e27\u0e2a\u0e15\u0e4c \u0e2a\u0e01\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006512 \u0e1a\u0e08.\u0e40\u0e19\u0e17\u0e35\u0e40\u0e27\u0e2a\u0e15\u0e4c \u0e2a\u0e01\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e39\u0e1b\u0e2b\u0e19\u0e49\u0e32 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 555\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006547\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19 \u0e1e\u0e25\u0e31\u0e2a2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006547 \u0e1a\u0e08.\u0e04\u0e25\u0e35\u0e19 \u0e1e\u0e25\u0e31\u0e2a2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e19\u0e49\u0e33\u0e22\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e19\u0e31\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001578\",\"name_th\":\"\u0e2b\u0e08.\u0e20.\u0e2a\u0e33\u0e40\u0e20\u0e32\u0e17\u0e2d\u0e07 999 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001578 \u0e2b\u0e08.\u0e20.\u0e2a\u0e33\u0e40\u0e20\u0e32\u0e17\u0e2d\u0e07 999 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-08 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b (\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003530\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003530 \u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0435569001090\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001090 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e25\u0e34\u0e1f\u0e15\u0e4c \u5efa\u8a2d 129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0443569000733\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e08\u0e1a\u0e35\u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000733 \u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e08\u0e1a\u0e35\u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-08 1000000 42101 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e25\u0e32\u0e19\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e07\u0e32\u0e19\u0e41\u0e2d\u0e2a\u0e1f\u0e31\u0e25\u0e15\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 242  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e33\u0e41\u0e2e\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0443569000741\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e32\u0e27\u0e38\u0e18 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000741 \u0e2b\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e32\u0e27\u0e38\u0e18 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-08 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0455569001413\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001413 \u0e1a\u0e08.\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 608  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e23\u0e30\u0e27\u0e35\u0e42\u0e2e\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0475569001456\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001456 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 334  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000875\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e48\u0e21\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47512\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47512\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000875 \u0e1a\u0e08.\u0e2b\u0e48\u0e21\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47512 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e49\u0e32\u0e1b\u0e39\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19 \u0e1b\u0e25\u0e2d\u0e01\u0e2b\u0e21\u0e2d\u0e19 \u0e1b\u0e25\u0e2d\u0e01\u0e1c\u0e49\u0e32\u0e19\u0e27\u0e21 \u0e1c\u0e49\u0e32\u0e19\u0e27\u0e21 \u0e1c\u0e49\u0e32\u0e2b\u0e48\u0e21 \u0e2b\u0e21\u0e2d\u0e19\u0e2b\u0e19\u0e38\u0e19 \u0e2b\u0e21\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07 \u0e17\u0e47\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e40\u0e1a\u0e32\u0e30\u0e23\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e1c\u0e49\u0e32\u0e1c\u0e37\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0503569004479\",\"name_th\":\"\u0e2b\u0e08.811 \u0e40\u0e14\u0e25\u0e15\u0e49\u0e32 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004479 \u0e2b\u0e08.811 \u0e40\u0e14\u0e25\u0e15\u0e49\u0e32 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c 2569-07-08 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a  \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5efa\u8a2d 470  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004487\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e19\u0e38\u0e19 \u0e19\u0e33 \u0e01\u0e34\u0e19\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004487 \u0e2b\u0e08.\u0e2b\u0e19\u0e38\u0e19 \u0e19\u0e33 \u0e01\u0e34\u0e19 2569-07-08 1000000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u88fd\u9020 257\/11-12  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e40\u0e17\u0e1e \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015413\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e23\u0e32\u0e22\u0e32 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015413 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e23\u0e32\u0e22\u0e32 \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a \u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u4e0d\u52d5\u7523 218\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015421\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e1a\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015421 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e1a\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e33\u0e19\u0e27\u0e13 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 (project management) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e02\u0e32 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 15\/6  \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015448\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e38\u0e4a\u0e01\u0e40\u0e0b\u0e48\u0e07\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015448 \u0e1a\u0e08.\u0e01\u0e38\u0e4a\u0e01\u0e40\u0e0b\u0e48\u0e07\u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 255\/19  \u0e16\u0e19\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000694\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e34\u0e28\u0e32 \u0e02\u0e49\u0e32\u0e27\u0e23\u0e32\u0e14\u0e41\u0e01\u0e07\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000694 \u0e2b\u0e08.\u0e23\u0e34\u0e28\u0e32 \u0e02\u0e49\u0e32\u0e27\u0e23\u0e32\u0e14\u0e41\u0e01\u0e07 2569-07-08 1000000 56101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e44\u0e27\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e42\u0e15\u0e4a\u0e30 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 104\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001364\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e25\u0e48\u0e32\u0e41\u0e15\u0e49\u0e21 \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001364 \u0e2b\u0e08.\u0e2a\u0e25\u0e48\u0e32\u0e41\u0e15\u0e49\u0e21 \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c 2569-07-08 1000000 70103 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29 (event organizer) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e27\u0e17\u0e35 \u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 91  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e15\u0e49\u0e19\u0e04\u0e48\u0e32-\u0e21\u0e48\u0e27\u0e07\u0e0a\u0e38\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 1 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001609\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e27\u0e19\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001609 \u0e1a\u0e08.\u0e19\u0e27\u0e19\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 367\/8  \u0e16\u0e19\u0e19\u0e09\u0e31\u0e15\u0e23\u0e44\u0e0a\u0e22 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0545569000777\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e0d\u0e48 39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000777 \u0e1a\u0e08.\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e0d\u0e48 39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e1e\u0e25\u0e31\u0e2a\u0e44\u0e0b\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0553569000406\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2d.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e1f.\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0553569000406 \u0e2b\u0e08.\u0e42\u0e2d.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e1f.\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 299  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0565569000572\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000572 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e42\u0e21\u0e2a\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 360  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0573569002115\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e27\u0e35\u0e22\u0e07\u0e25\u0e2d \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002115 \u0e2b\u0e08.\u0e40\u0e27\u0e35\u0e22\u0e07\u0e25\u0e2d \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-08 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e23\u0e27\u0e14 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004403\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e23\u0e17\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004403 \u0e1a\u0e08.\u0e44\u0e17\u0e23\u0e17\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e01\u0e49\u0e2d\u0e19 \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 204  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001495\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e35\u0e17\u0e35\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001495 \u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e1a\u0e35\u0e17\u0e35 2569-07-08 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001509\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e2d\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001509 \u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e2d\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21 2569-07-08 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001517\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001517 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e0a\u0e47\u0e2d\u0e1b 2569-07-08 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0615569000512\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000512 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0675569001454\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e08 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001454 \u0e1a\u0e08.\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e08 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003081\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003081 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 134\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003090\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e2a\u0e01\u0e32\u0e22 \u0e40\u0e08\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003090 \u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e2a\u0e01\u0e32\u0e22 \u0e40\u0e08\u0e40\u0e19\u0e2d\u0e23\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e27\u0e49\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 303  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002506\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e33\u0e23\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002506 \u0e1a\u0e08.\u0e14\u0e33\u0e23\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002514\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e0f\u0e34\u0e21\u0e32 \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002514 \u0e1a\u0e08.\u0e1b\u0e0f\u0e34\u0e21\u0e32 \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e16\u0e40\u0e2e\u0e35\u0e4a\u0e22\u0e1a \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e40\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e23\u0e16\u0e42\u0e1f\u0e25\u0e4c\u0e01\u0e25\u0e34\u0e1f\u0e17\u0e4c \u0e1b\u0e31\u0e49\u0e21\u0e25\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e31\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 198\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000617\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e32 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000617 \u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e32 \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e01 2569-07-08 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5efa\u8a2d 478\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002077\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e34\u0e2a \u0e2a\u0e1b\u0e32\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002077 \u0e1a\u0e08.\u0e2d\u0e23\u0e34\u0e2a \u0e2a\u0e1b\u0e32\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e04\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e27 \u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e34\u0e27\u0e15\u0e31\u0e27 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e25\u0e14\u0e19\u0e4d\u0e49\u0e32\u0e2b\u0e19\u0e31\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 249\/268-269  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002085\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e32\u0e42\u0e19\u0e48 \u0e2d\u0e35\u0e27\u0e35\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e19   \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002085 \u0e1a\u0e08.\u0e2d\u0e23\u0e32\u0e42\u0e19\u0e48 \u0e2d\u0e35\u0e27\u0e35\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e19   \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006927\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006927 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47190 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006935\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e23\u0e38\u0e48\u0e07\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006935 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e23\u0e38\u0e48\u0e07\u0e19\u0e34\u0e21\u0e34\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e28\u0e29\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e2d\u0e31\u0e14\u0e01\u0e49\u0e2d\u0e19 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 42\/91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006943\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e44\u0e21\u0e23\u0e4c \u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006943 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e44\u0e21\u0e23\u0e4c \u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/21  \u0e16\u0e19\u0e1925\u0e21\u0e01\u0e23\u0e32 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007141\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e2a\u0e4c \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007141 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e23\u0e2a\u0e4c \u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e01\u0e49\u0e27\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e01\u0e49\u0e27\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1d\u0e32\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1d\u0e32\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2b\u0e25\u0e2d\u0e14\u0e14\u0e39\u0e14 \u0e0a\u0e49\u0e2d\u0e19 \u0e2a\u0e49\u0e2d\u0e21 \u0e21\u0e35\u0e14 \u0e16\u0e49\u0e27\u0e22 \u0e0a\u0e32\u0e21 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e16\u0e38\u0e07 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e2b\u0e48\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007168\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e14\u0e35\u0e1a\u0e35 \u0e42\u0e19\u0e27\u0e32 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007168 \u0e1a\u0e08.\u0e40\u0e04\u0e14\u0e35\u0e1a\u0e35 \u0e42\u0e19\u0e27\u0e32 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e15 \u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38  \u0e41\u0e1c\u0e07\u0e27\u0e07\u0e08\u0e23 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 16\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0805569002611\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e21\u0e17\u0e31\u0e25\u0e0a\u0e35\u0e17 \u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25910\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25910\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002611 \u0e1a\u0e08.\u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e21\u0e17\u0e31\u0e25\u0e0a\u0e35\u0e17 \u0e17\u0e38\u0e48\u0e07\u0e2a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 25910 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e17\u0e31\u0e25\u0e0a\u0e35\u0e17 \u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e40\u0e21\u0e17\u0e31\u0e25\u0e0a\u0e35\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 532  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0815569002033\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e35\u0e19\u0e2a\u0e4c \u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002033 \u0e1a\u0e08.\u0e22\u0e35\u0e19\u0e2a\u0e4c \u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e22\u0e35\u0e19\u0e2a\u0e4c \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e22\u0e35\u0e19\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e31\u0e19\u0e21\u0e34\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47  \u0e16\u0e19\u0e19\u0e19\u0e32\u0e40\u0e15\u0e22 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0825569001118\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e40\u0e1b\u0e23\u0e0b\u0e32 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001118 \u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e40\u0e1b\u0e23\u0e0b\u0e32 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a (\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e39\u0e41\u0e25\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 37\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0843569001311\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e39\u0e21\u0e34 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 1977\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001311 \u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e39\u0e21\u0e34 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 1977 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 20\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005457\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e22\u0e40\u0e27\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005457 \u0e1a\u0e08.\u0e0b\u0e2d\u0e22\u0e40\u0e27\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e15\u0e30 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 141\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e1a\u0e39\u0e19\u0e33 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005473\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e1b\u0e32\u0e23\u0e4c\u0e04\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005473 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e1b\u0e32\u0e23\u0e4c\u0e04\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005481\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35. \u0e17\u0e35. \u0e40\u0e2d. 1976 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005481 \u0e1a\u0e08.\u0e14\u0e35. \u0e17\u0e35. \u0e40\u0e2d. 1976 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 369\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0935569000803\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000803 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0945569000684\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e17\u0e34\u0e01\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93120\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93120\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000684 \u0e1a\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e17\u0e34\u0e01\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 1000000 93120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u82b8\u8853\u30fb\u5a2f\u697d 140\/3  \u0e16\u0e19\u0e19\u0e22\u0e30\u0e23\u0e31\u0e07 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0963569000283\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2e\u0e1f\u0e40\u0e27\u0e48\u0e19\u0e17\u0e2d\u0e19 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000283 \u0e2b\u0e08.\u0e40\u0e2e\u0e1f\u0e40\u0e27\u0e48\u0e19\u0e17\u0e2d\u0e19 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 2569-07-08 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1e\u0e39\u0e25\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 888  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569007013\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e07\u0e29\u0e4c\u0e2a\u0e38\u0e18\u0e34\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007013 \u0e2b\u0e08.\u0e1e\u0e07\u0e29\u0e4c\u0e2a\u0e38\u0e18\u0e34\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 2569-07-07 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e16 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35\u0e23\u0e16 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e1e\u0e48\u0e19\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e17 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e16  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e16 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/90  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007021\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e19\u0e38\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007021 \u0e2b\u0e08.\u0e2d\u0e19\u0e38\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-07 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113\/85  \u0e0b\u0e2d\u0e22 \u0e0a\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2d\u0e38\u0e17\u0e34\u0e28 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007030\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08\u0e40\u0e04 \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007030 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08\u0e40\u0e04 \u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c 2569-07-07 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 468\/128  \u0e16\u0e19\u0e19\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127606\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e2d\u0e2d\u0e1f \u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127606 \u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e2d\u0e2d\u0e1f \u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u6559\u80b2 289\/273  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e14\u0e2d\u0e30\u0e40\u0e1a\u0e2a \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 77 (\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 1) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127614\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e38\u0e23\u0e38\u0e0b\u0e32\u0e42\u0e15\u0e30 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127614 \u0e1a\u0e08.\u0e1f\u0e38\u0e23\u0e38\u0e0b\u0e32\u0e42\u0e15\u0e30 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47739 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e19\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/65  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127631\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e40\u0e2d \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127631 \u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e40\u0e2d \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 45403 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e14\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 293\/58  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 69 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127657\",\"name_th\":\"\u0e1a\u0e08.729 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127657 \u0e1a\u0e08.729 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47190 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12  \u0e0b\u0e2d\u0e22 \u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127665\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e01\u0e2d\u0e2d\u0e1f \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127665 \u0e1a\u0e08.\u0e04\u0e34\u0e01\u0e2d\u0e2d\u0e1f \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 14 \u0e41\u0e22\u0e01 13 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127673\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74901\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74901\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127673 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 74901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 250\/4  \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127681\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e32\u0e27\u0e2d\u0e32\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127681 \u0e1a\u0e08.\u0e40\u0e0a\u0e32\u0e27\u0e2d\u0e32\u0e20\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32\u0e1a\u0e32\u0e25\u0e4c\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e22\u0e32\u0e2b\u0e21\u0e48\u0e2d\u0e07 \u0e22\u0e32\u0e14\u0e21  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/487  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e32\u0e0b\u0e48\u0e32\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25-\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 2 \u0e0b\u0e2d\u0e22 5\/2 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127690\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127690 \u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 64202 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u91d1\u878d\u30fb\u4fdd\u967a 109\/146  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 21 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127711\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e13\u0e35\u0e21\u0e19\u0e15\u0e23\u0e32 \u0e2a\u0e42\u0e15\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127711 \u0e1a\u0e08.\u0e21\u0e13\u0e35\u0e21\u0e19\u0e15\u0e23\u0e32 \u0e2a\u0e42\u0e15\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127746\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e21\u0e1e\u0e25\u0e31\u0e2a\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127746 \u0e1a\u0e08.\u0e17\u0e35\u0e21\u0e1e\u0e25\u0e31\u0e2a\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 53\/52  \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e2f\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d6\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127762\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49\u0e1e\u0e2d\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127762 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49\u0e1e\u0e2d\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e02\u0e19 \u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e27\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e14\u0e35 (wellness) \u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 98\/195  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e23\u0e32\u0e23\u0e21\u0e22\u0e4c \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25-\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 \u0e0b\u0e2d\u0e22 9\/1 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127789\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127789 \u0e1a\u0e08.\u0e2d\u0e34\u0e21\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e08\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127797\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e08\u0e34\u0e19 \u0e0b\u0e32\u0e25\u0e32\u0e40\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10616\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10616\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127797 \u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e08\u0e34\u0e19 \u0e0b\u0e32\u0e25\u0e32\u0e40\u0e1b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 10616 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e0b\u0e32\u0e25\u0e32\u0e40\u0e1b\u0e32 \u0e02\u0e19\u0e21\u0e08\u0e35\u0e1a \u88fd\u9020 142\/53  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127851\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e2d \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127851 \u0e1a\u0e08.\u0e22\u0e39\u0e40\u0e2d\u0e47\u0e21\u0e44\u0e2d \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e02\u0e49\u0e2d\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/223  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e0b\u0e21\u0e34\u0e2a \u0e1a\u0e25\u0e2d\u0e2a\u0e0b\u0e31\u0e48\u0e21 \u0e41\u0e2d\u0e17 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 64 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127878\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e13\u0e34\u0e28 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127878 \u0e1a\u0e08.\u0e2d\u0e13\u0e34\u0e28 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 689  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127908\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e0b \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127908 \u0e1a\u0e08.\u0e19\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e0b \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 66191 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u91d1\u878d\u30fb\u4fdd\u967a 68\/3  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 43 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127916\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e42\u0e18\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127916 \u0e1a\u0e08.\u0e1e\u0e32\u0e42\u0e18\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 28\/208  \u0e16\u0e19\u0e19\u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127924\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e41\u0e2d\u0e25 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127924 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e41\u0e2d\u0e25 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 199  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127941\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e17\u0e35 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127941 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e17\u0e35 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 96309 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e02\u0e2d\u0e07\u0e40\u0e40\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 4  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 29 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127983\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127983 \u0e1a\u0e08.\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e2a\u0e35\u0e1f\u0e31\u0e19 \u0e19\u0e4d\u0e49\u0e32\u0e22\u0e32\u0e1a\u0e49\u0e27\u0e19\u0e1b\u0e32\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1b\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e1f\u0e31\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 455\/29  \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127991\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1f\u0e27\u0e4c \u0e41\u0e2d\u0e47\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127991 \u0e1a\u0e08.\u0e44\u0e1f\u0e27\u0e4c \u0e41\u0e2d\u0e47\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e01\u0e4a\u0e2a \u0e15\u0e32\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u5efa\u8a2d 43,43\/1  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 66\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128009\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e40\u0e08 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128009 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e40\u0e08 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128025\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e21\u0e42\u0e01\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32501\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32501\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128025 \u0e1a\u0e08.\u0e41\u0e2e\u0e21\u0e42\u0e01\u0e49  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 32501 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u88fd\u9020 201\/539  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e23\u0e38\u0e13\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 54\/1 \u0e41\u0e22\u0e01 4-12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128033\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e01\u0e34\u0e15\u0e34\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128033 \u0e1a\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e01\u0e34\u0e15\u0e34\u0e1e\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e0a\u0e38\u0e14\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/219  \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e25\u0e33\u0e40\u0e08\u0e35\u0e22\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128041\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e41\u0e2d\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128041 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e41\u0e2d\u0e19\u0e34\u0e21\u0e2d\u0e25 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e09\u0e35\u0e14\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 796  \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128076\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e2d\u0e35\u0e42\u0e04 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128076 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e2d\u0e35\u0e42\u0e04 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 57 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128084\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e25\u0e32\u0e22 \u0e40\u0e14\u0e2d \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128084 \u0e1a\u0e08.\u0e1f\u0e25\u0e32\u0e22 \u0e40\u0e14\u0e2d \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 998\/99  \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1e\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128106\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128106 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/43  \u0e0b\u0e2d\u0e22 \u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e236 \u0e0b\u0e2d\u0e227 \u0e41\u0e22\u0e013-6 (\u0e2a\u0e34\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e32\u0e19\u0e35) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128114\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e2a\u0e15\u0e4c\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128114 \u0e1a\u0e08.\u0e27\u0e32\u0e2a\u0e15\u0e4c\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e42\u0e04\u0e21\u0e44\u0e1f led \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e35 23 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128131\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e08\u0e35 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128131 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e08\u0e35 \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 96309 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e02\u0e2d\u0e07\u0e40\u0e40\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 2523  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128149\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e07\u0e01\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128149 \u0e1a\u0e08.\u0e2d\u0e34\u0e07\u0e01\u0e31\u0e2a \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b (outsourcing service) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 674\/7  \u0e0b\u0e2d\u0e22 \u0e1e\u0e0d\u0e32\u0e19\u0e32\u0e04 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128157\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e39\u0e23\u0e48\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128157 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e39\u0e23\u0e48\u0e32 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e32\u0e01\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c e-marketplace (electronic marketplace)  (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 838\/130  \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1e\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128173\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 789 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128173 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 789 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 49339 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e40\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e1e\u0e48\u0e27\u0e07\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e23\u0e16\u0e22\u0e01 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u904b\u8f38\u30fb\u7269\u6d41 81\/257  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128246\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e32\u0e17\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128246 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e32\u0e17\u0e4c 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 85\/318  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 20 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 - \u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128254\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e18\u0e19\u0e32 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128254 \u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e18\u0e19\u0e32 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 74109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e2a\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e07\u0e32\u0e19\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 13  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e01\u0e23\u0e30\u0e14\u0e35\u0e48 41 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128297\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e37\u0e48\u0e19\u0e21\u0e32\u0e01\u0e47\u0e23\u0e27\u0e22 \u0e44\u0e21\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128297 \u0e1a\u0e08.\u0e15\u0e37\u0e48\u0e19\u0e21\u0e32\u0e01\u0e47\u0e23\u0e27\u0e22 \u0e44\u0e21\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32\u0e07\u0e32\u0e19\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 106  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 4 (\u0e2a\u0e21\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128327\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e0f\u0e34\u0e21\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128327 \u0e1a\u0e08.\u0e1b\u0e0f\u0e34\u0e21\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 56\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128343\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e21\u0e2d\u0e19\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128343 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e14\u0e21\u0e2d\u0e19\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 59202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e1c\u0e25\u0e34\u0e15\u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1e\u0e25\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e25\u0e30\u0e04\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1c\u0e25\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2b\u0e19\u0e36\u0e48\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 888  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c 11  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 10-405 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128351\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e01\u0e2a\u0e42\u0e15\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128351 \u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e01\u0e2a\u0e42\u0e15\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e17\u0e4d\u0e32 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 (application) \u0e23\u0e31\u0e1a\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28(it) \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 349  \u0e2d\u0e32\u0e04\u0e32\u0e23sj infinite i business complex \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 20 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35-\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128360\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128360 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0a\u0e35\u0e2a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e35\u0e2a\u0e2a\u0e14 \u0e0a\u0e35\u0e2a\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e48\u0e2d\u0e19 \u0e0a\u0e35\u0e2a\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e02\u0e47\u0e07 \u0e0a\u0e35\u0e2a\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0a\u0e35\u0e2a\u0e1c\u0e07 \u0e0a\u0e35\u0e2a\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e0a\u0e35\u0e2a\u0e1f\u0e23\u0e35\u0e0b\u0e14\u0e23\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e35\u0e2a\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u88fd\u9020 98\/49  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a-\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128378\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128378 \u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c \u0e2a\u0e40\u0e1b\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a-\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 237  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128394\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e35 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128394 \u0e1a\u0e08.\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e35 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e08\u0e32\u0e01\u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e17\u0e47\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e40\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 91\/67  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e40\u0e40\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128459\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33141\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33141\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128459 \u0e1a\u0e08.\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 33141 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1b\u0e31\u0e49\u0e21\u0e19\u0e49\u0e33 \u0e22\u0e32\u0e07\u0e41\u0e25\u0e30\u0e42\u0e2d\u0e23\u0e34\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 56\/24  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e2a\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128483\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128483 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 20\/106  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e21\u0e34\u0e15\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128491\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e0b\u0e35\u0e27\u0e34\u0e25\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128491 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e0b\u0e35\u0e27\u0e34\u0e25\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 18  \u0e0b\u0e2d\u0e22 \u0e41\u0e22\u0e01\u0e2a\u0e27\u0e19\u0e2a\u0e22\u0e32\u0e21 3 \u0e41\u0e22\u0e01 13 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128505\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e48\u0e21\u0e2a\u0e38\u0e02 \u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128505 \u0e1a\u0e08.\u0e23\u0e48\u0e21\u0e2a\u0e38\u0e02 \u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 87301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e1e\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e1e\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e44\u0e1b-\u0e01\u0e25\u0e31\u0e1a \u533b\u7642\u30fb\u798f\u7949 89\/864  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 81 \u0e41\u0e22\u0e01 3-41 \u0e16\u0e19\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002232\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e1e\u0e23\u0e28\u0e23\u0e35 \u0e1a\u0e31\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002232 \u0e2b\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e1e\u0e23\u0e28\u0e23\u0e35 \u0e1a\u0e31\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-07 1000000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e48\u0e07\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e15\u0e32\u0e21\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 995\/44  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022367\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e49\u0e14\u0e19\u0e34\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022367 \u0e1a\u0e08.\u0e42\u0e04\u0e49\u0e14\u0e19\u0e34\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c (application) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 59\/197  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 - \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022375\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49209\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49209\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022375 \u0e1a\u0e08.\u0e2a\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e04\u0e38\u0e13 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 49209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e42\u0e14\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e1a\u0e31\u0e2a         \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 2102\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022391\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e1f\u0e1f\u0e35\u0e48\u0e40\u0e1a\u0e04\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022391 \u0e1a\u0e08.\u0e1e\u0e31\u0e1f\u0e1f\u0e35\u0e48\u0e40\u0e1a\u0e04\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u88fd\u9020 713\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022421\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022421 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 87301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e07 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e1a\u0e32\u0e25 \u0e14\u0e39\u0e41\u0e25 \u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19\u0e41\u0e25\u0e30\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a \u533b\u7642\u30fb\u798f\u7949 88\/119  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e2a\u0e32\u0e17\u0e23-\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022481\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e38\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e01\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022481 \u0e1a\u0e08.\u0e0b\u0e38\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e01\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e02\u0e27\u0e14\u0e41\u0e01\u0e49\u0e27 \u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1d\u0e32\u0e41\u0e25\u0e30\u0e08\u0e38\u0e01\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2b\u0e31\u0e27\u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c \u0e09\u0e25\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 899\/383  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022502\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022502 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 168\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022511\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e04\u0e23\u0e2a\u0e17\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022511 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e04\u0e23\u0e2a\u0e17\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e44\u0e21\u0e42\u0e04\u0e23\u0e0a\u0e34\u0e1e\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e07\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 468\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025242\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e0a\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e1e\u0e47\u0e17\u0e0a\u0e49\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025242 \u0e1a\u0e08.\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e0a\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e1e\u0e47\u0e17\u0e0a\u0e49\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\/\u0e2a\u0e48\u0e07  \u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e31\u0e48\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e02\u0e19\u0e21 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/77  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 177 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025251\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e47\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025251 \u0e1a\u0e08.\u0e40\u0e17\u0e47\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47640 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 25 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025285\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e25 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025285 \u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e25 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 58112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 98\/83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1b\u0e39\u0e48\u0e40\u0e17\u0e1e-\u0e1b\u0e39\u0e48\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025293\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025293 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025307\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46634\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46634\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025307 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46634 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14  \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c 22 \u0e41\u0e22\u0e01 10 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025315\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e11\u0e39\u0e23\u0e22\u0e4c\u0e40\u0e21\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025315 \u0e1a\u0e08.\u0e27\u0e34\u0e11\u0e39\u0e23\u0e22\u0e4c\u0e40\u0e21\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 diy (\u0e14\u0e35\u0e44\u0e2d\u0e27\u0e32\u0e22) \u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u0e07\u0e32\u0e19\u0e44\u0e21\u0e49\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025331\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e2a\u0e40\u0e1b\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025331 \u0e1a\u0e08.\u0e40\u0e04 \u0e2a\u0e40\u0e1b\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 31001 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49\u0e08\u0e23\u0e34\u0e07 \u88fd\u9020 40\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025340\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025340 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5efa\u8a2d 50\/92  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025374\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e19 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025374 \u0e1a\u0e08.\u0e21\u0e34\u0e19 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e17\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30           \u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 212\/158  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e38\u0e13\u0e32\u0e25\u0e31\u0e22 \u0e04\u0e2d\u0e23\u0e4c\u0e17\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025382\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e1e\u0e35 1966 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025382 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e1e\u0e35 1966 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 71101 \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48  \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 271\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025439\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e34\u0e0a \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025439 \u0e1a\u0e08.\u0e04\u0e23\u0e34\u0e0a \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/60  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e2d\u0e23\u0e34 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 - \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025455\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e39\u0e42\u0e01\u0e30 \u0e0a\u0e49\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025455 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e39\u0e42\u0e01\u0e30 \u0e0a\u0e49\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/890  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025471\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e21\u0e32\u0e01 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025471 \u0e1a\u0e08.\u0e14\u0e35\u0e21\u0e32\u0e01 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 72\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025480\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e01\u0e1b\u0e4a\u0e2d\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e217 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56103\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56103\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025480 \u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e01\u0e1b\u0e4a\u0e2d\u0e01\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e217 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025498\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025498 \u0e1a\u0e08.\u0e27\u0e34\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025528\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025528 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46108 \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e14\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e14\u0e02\u0e32\u0e22 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 107\/324  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020828\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020828 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 49334 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 5\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020836\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020836 \u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e49\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 44\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e13\u0e32\u0e2a\u0e34\u0e23\u0e34 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e04\u0e25\u0e2d\u0e072 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020844\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35\u0e21\u0e35\u0e14\u0e35 \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020844 \u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35\u0e21\u0e35\u0e14\u0e35 \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e1a\u0e39\u0e18\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e41\u0e01\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u82b8\u8853\u30fb\u5a2f\u697d 89\/36  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e23\u0e32\u0e0d\u0e2a\u0e34\u0e23\u0e34 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c - \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020852\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d \u0e01\u0e23\u0e35\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020852 \u0e1a\u0e08.\u0e44\u0e2d \u0e01\u0e23\u0e35\u0e19 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e39\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e49\u0e19\u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e01\u0e31\u0e0d\u0e0a\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e37\u0e0a\u0e01\u0e31\u0e0d\u0e0a\u0e32 \u0e01\u0e31\u0e0d\u0e0a\u0e07 \u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 (\u0e40\u0e0a\u0e48\u0e19 \u0e43\u0e1a \u0e14\u0e2d\u0e01 \u0e23\u0e32\u0e01 \u0e25\u0e33\u0e15\u0e49\u0e19) \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52\/035  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020861\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e04\u0e25\u0e35\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020861 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e04\u0e25\u0e35\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 81210 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 41\/25   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 41\/25 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020887\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020887 \u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e32 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e1e\u0e32\u0e22 \u0e40\u0e04\u0e49\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 19\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020895\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e32 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020895 \u0e1a\u0e08.\u0e19\u0e04\u0e23\u0e32 \u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 19\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020909\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e16\u0e32\u0e27\u0e23 \u0e40\u0e1f\u0e23\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020909 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e16\u0e32\u0e27\u0e23 \u0e40\u0e1f\u0e23\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e02\u0e36\u0e49\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020917\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e21\u0e2d\u0e19\u0e15\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020917 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e21\u0e2d\u0e19\u0e15\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 71\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020925\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020925 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46900 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020933\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e0b\u0e35 \u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020933 \u0e1a\u0e08.\u0e1e\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e0b\u0e35 \u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 49\/149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004431\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e17\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"19202\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"19202\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004431 \u0e1a\u0e08.\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e01\u0e23\u0e35\u0e19 \u0e40\u0e17\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 19202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e02\u0e22\u0e30 \u88fd\u9020 34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19- \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001521\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e31\u0e0d\u0e0d\u0e32 2021 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001521 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e31\u0e0d\u0e0d\u0e32 2021 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev changing station) \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e01\u0e48\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 117\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000736\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e21\u0e19\u0e21\u0e07\u0e04\u0e25 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 168\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000736 \u0e2b\u0e08.\u0e41\u0e21\u0e19\u0e21\u0e07\u0e04\u0e25 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 168 2569-07-07 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51\/127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002480\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46592\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46592\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002480 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46592 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 141\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002843\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e01\u0e4a\u0e2a\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47735\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47735\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002843 \u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e01\u0e4a\u0e2a 2569-07-07 1000000 47735 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a \u0e2b\u0e31\u0e27\u0e41\u0e01\u0e4a\u0e2a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e16\u0e31\u0e07\u0e01\u0e4a\u0e32\u0e0b \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035646\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46317\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46317\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035646 \u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46317 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035654\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e1f\u0e25\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66123\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66123\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035654 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e1f\u0e25\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 66123 \u0e23\u0e31\u0e1a\u0e41\u0e25\u0e01\u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e01\u0e38\u0e25\u0e40\u0e07\u0e34\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 99\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035689\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e0a\u0e32 \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035689 \u0e1a\u0e08.\u0e19\u0e34\u0e0a\u0e32 \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035697\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e39\u0e1a\u0e25\u0e39\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e1a\u0e35\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035697 \u0e1a\u0e08.\u0e17\u0e23\u0e39\u0e1a\u0e25\u0e39\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e1a\u0e35\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 39\/132-133  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e39\u0e1a\u0e39\u0e25\u0e2d\u0e2d\u0e2a\u0e0b\u0e35\u0e1a\u0e32\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 39\/132-133 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e1a\u0e38\u0e0d\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e16\u0e19\u0e19\u0e40\u0e02\u0e32\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035701\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035701 \u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e40\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e19\u0e49\u0e33 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 9\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035719\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d.\u0e27\u0e32\u0e22. \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035719 \u0e1a\u0e08.\u0e40\u0e2d.\u0e27\u0e32\u0e22. \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c (\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17) \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 148\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035727\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035727 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21  \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035760\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 1975 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035760 \u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 1975 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e17\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035778\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035778 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1e\u0e32\u0e22 \u0e40\u0e04\u0e49\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 29\/10  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e08\u0e32\u0e23\u0e38\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035808\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10769\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10769\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035808 \u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 10769 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 20\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035816\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e28\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035816 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e28\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e19\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 64\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035841\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035841 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e08\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 82\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035867\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e2a\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19\u0e0a\u0e25 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035867 \u0e1a\u0e08.\u0e2d\u0e35\u0e2a\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19\u0e0a\u0e25 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 397\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035875\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e04\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035875 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e04\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 99\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035905\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e04 \u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035905 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e04 \u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 133\/46  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035913\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c \u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035913 \u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c \u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e01\u0e25\u0e36\u0e07 \u0e40\u0e08\u0e32\u0e30 \u0e04\u0e27\u0e49\u0e32\u0e19 \u0e01\u0e31\u0e14 \u0e44\u0e2a \u0e40\u0e08\u0e35\u0e22\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 9\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001201\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e32\u0e13\u0e38\u0e1e\u0e07\u0e28\u0e4c\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 \u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001201 \u0e2b\u0e08.\u0e20\u0e32\u0e13\u0e38\u0e1e\u0e07\u0e28\u0e4c\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 \u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-07 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e1a\u0e23\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0213569001227\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001227 \u0e2b\u0e08.\u0e2a\u0e38\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-07 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 597\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009009\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e42\u0e2e\u0e211992 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009009 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e42\u0e2e\u0e211992 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 68201 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 222\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009017\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009017 \u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009033\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.26 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009033 \u0e1a\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.26 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 25999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e01\u0e25\u0e36\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19\u0e07\u0e32\u0e19\u0e21\u0e34\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e07\u0e32\u0e19\u0e40\u0e08\u0e35\u0e22\u0e23\u0e43\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 310\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009041\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009041 \u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56101 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 174  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002128\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e23\u0e27\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002128 \u0e1a\u0e08.\u0e2a\u0e33\u0e23\u0e27\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14 \u0e1c\u0e25\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e01\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e25\u0e33\u0e44\u0e22 \u0e21\u0e30\u0e02\u0e32\u0e21 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e2d\u0e21\u0e43\u0e2b\u0e0d\u0e48 \u0e21\u0e31\u0e19\u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e31\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e1c\u0e31\u0e01\u0e2a\u0e14\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 225\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003647\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63990\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63990\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003647 \u0e1a\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 63990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e41\u0e04\u0e2a\u0e15\u0e4c\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 244\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0253569000492\",\"name_th\":\"\u0e2b\u0e08.\u0e2a.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e20\u0e39\u0e01\u0e31\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0253569000492 \u0e2b\u0e08.\u0e2a.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e20\u0e39\u0e01\u0e31\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-07 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 223\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569001938\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e1f\u0e23\u0e17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001938 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e1f\u0e23\u0e17 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23  \u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32?\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 430\/527  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e17\u0e23(\u0e17\u0e48\u0e32\u0e15\u0e39\u0e21) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569001946\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001946 \u0e1a\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 265\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002591\",\"name_th\":\"\u0e2b\u0e08.\u0e1b.\u0e28\u0e31\u0e01\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002591 \u0e2b\u0e08.\u0e1b.\u0e28\u0e31\u0e01\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-07 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e02\u0e38\u0e19\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30 \u0e02\u0e38\u0e14\u0e1a\u0e48\u0e2d \u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01\u0e04\u0e39\u0e04\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e14\u0e34\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 320  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007048\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007048 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/204  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e 19 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007072\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e23\u0e4c \u0e21\u0e34\u0e19\u0e34\u0e21\u0e31\u0e21 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007072 \u0e1a\u0e08.\u0e41\u0e1a\u0e23\u0e4c \u0e21\u0e34\u0e19\u0e34\u0e21\u0e31\u0e21 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e08\u0e2d\u0e20\u0e32\u0e1e\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 347  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 25 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007081\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e25\u0e34\u0e01\u0e0b\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007081 \u0e1a\u0e08.\u0e1f\u0e25\u0e34\u0e01\u0e0b\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 1098\/36  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007099\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e25\u0e32\u0e0a\u0e31\u0e22 \u0e41\u0e2d\u0e2a\u0e1f\u0e31\u0e25\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007099 \u0e1a\u0e08.\u0e28\u0e34\u0e25\u0e32\u0e0a\u0e31\u0e22 \u0e41\u0e2d\u0e2a\u0e1f\u0e31\u0e25\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e22\u0e32\u0e07\u0e21\u0e30\u0e15\u0e2d\u0e22 \u0e1b\u0e39\u0e19 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e16\u0e19\u0e19 \u5efa\u8a2d 9\/142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0325569001171\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e31\u0e15\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001171 \u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e31\u0e15\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32            \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33 \u0e23\u0e16\u0e44\u0e16 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 232  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0363569000831\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e22\u0e39\u0e40\u0e04 \u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15168\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000831 \u0e2b\u0e08.\u0e17\u0e35\u0e22\u0e39\u0e40\u0e04 \u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15168 2569-07-07 1000000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e16\u0e48\u0e16\u0e2d\u0e19\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e1b\u0e25\u0e14\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e1a\u0e48\u0e07\u0e44\u0e16\u0e48\u0e16\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e07\u0e34\u0e19\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02\u0e2b\u0e19\u0e35\u0e49\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e41\u0e1a\u0e48\u0e07\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e23\u0e27\u0e21\u0e42\u0e14\u0e22\u0e04\u0e23\u0e2d\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e42\u0e2d\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e42\u0e14\u0e22\u0e04\u0e23\u0e2d\u0e07\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e17\u0e33\u0e02\u0e49\u0e2d\u0e15\u0e01\u0e25\u0e07\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e04\u0e48\u0e32\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33 \u0e08\u0e33\u0e19\u0e2d\u0e07 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u91d1\u878d\u30fb\u4fdd\u967a 426  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0365569001414\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e19\u0e01\u0e27\u0e23\u0e23\u0e13 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10293\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10293\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001414 \u0e1a\u0e08.\u0e01\u0e19\u0e01\u0e27\u0e23\u0e23\u0e13 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 10293 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e27 \u0e19\u0e49\u0e33\u0e1b\u0e25\u0e32\u0e2b\u0e27\u0e32\u0e19 \u88fd\u9020 125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0393569000327\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e31\u0e0d\u0e0d\u0e32\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2026\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000327 \u0e2b\u0e08.\u0e01\u0e31\u0e0d\u0e0d\u0e32\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2026 2569-07-07 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e02\u0e38\u0e14 \u0e25\u0e2d\u0e01 \u0e2b\u0e49\u0e27\u0e22 \u0e2b\u0e19\u0e2d\u0e07 \u0e04\u0e25\u0e2d\u0e07 \u0e1a\u0e36\u0e07 \u0e2a\u0e23\u0e30\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e33\u0e1d\u0e32\u0e22\u0e01\u0e31\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30\u0e1a\u0e48\u0e2d\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 82  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0403569002973\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e19\u0e35\u0e48 \u0e1a\u0e25\u0e39\u0e21 \u0e40\u0e19\u0e2d\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"88901\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"88901\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002973 \u0e2b\u0e08.\u0e17\u0e35\u0e19\u0e35\u0e48 \u0e1a\u0e25\u0e39\u0e21 \u0e40\u0e19\u0e2d\u0e2a\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 2569-07-07 1000000 88901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e14\u0e47\u0e01\u0e1b\u0e10\u0e21\u0e27\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e14\u0e39\u0e41\u0e25\u0e40\u0e14\u0e47\u0e01 \u0e2a\u0e31\u0e0d\u0e08\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e39\u0e41\u0e25 \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e14\u0e39 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e02\u0e49\u0e32\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u533b\u7642\u30fb\u798f\u7949 319  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569002981\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002981 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2569-07-07 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 281  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001551\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e22\u0e19\u0e15\u0e4c 51\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001551 \u0e2b\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e22\u0e19\u0e15\u0e4c 51 2569-07-07 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e2a\u0e35\u0e02\u0e49\u0e32\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e31\u0e14\u0e02\u0e49\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001560\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e0d\u0e34\u0e07\u0e2d\u0e23\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001560 \u0e2b\u0e08.\u0e2b\u0e0d\u0e34\u0e07\u0e2d\u0e23 2569-07-07 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003491\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e17\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e1e\u0e25\u0e35\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003491 \u0e1a\u0e08.\u0e1a\u0e35\u0e17\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e1e\u0e25\u0e35\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 84\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003513\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23951\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23951\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003513 \u0e1a\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 23951 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1c\u0e2a\u0e21\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2b\u0e25\u0e48\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u88fd\u9020 314  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0435569001065\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e35 \u0e2a\u0e31\u0e07\u0e06\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001065 \u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e35 \u0e2a\u0e31\u0e07\u0e06\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e06\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e18\u0e39\u0e1b \u0e40\u0e17\u0e35\u0e22\u0e19 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e1b\u0e25\u0e27 \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e41\u0e2b\u0e49\u0e07 \u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e31\u0e22  \u0e2b\u0e34\u0e49\u0e07\u0e1a\u0e39\u0e0a\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e31\u0e07\u0e06\u0e17\u0e32\u0e19 \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (platform online) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0435569001073\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 - \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001073 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 - \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19 survey (\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e27\u0e08)  \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u5efa\u8a2d 230\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0445569001642\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e01\u0e30\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001642 \u0e1a\u0e08.\u0e01\u0e34\u0e01\u0e30\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\/\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19-\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0453569000989\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e48\u0e32\u0e15\u0e48\u0e32\u0e22 \u0e2b\u0e21\u0e39\u0e17\u0e2d\u0e07\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569000989 \u0e2b\u0e08.\u0e08\u0e48\u0e32\u0e15\u0e48\u0e32\u0e22 \u0e2b\u0e21\u0e39\u0e17\u0e2d\u0e07 2569-07-07 1000000 46204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e38\u0e01\u0e23\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e48\u0e32\u0e1a\u0e32\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001405\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001405 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 186  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19232 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0465569000841\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35\u0e40\u0e04 \u0e2d\u0e35\u0e27\u0e35\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000841 \u0e1a\u0e08.\u0e27\u0e35\u0e1e\u0e35\u0e40\u0e04 \u0e2d\u0e35\u0e27\u0e35\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32  \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 389  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0475569001448\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46314\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46314\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001448 \u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e0d\u0e0d\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46314 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e21\u0e2a\u0e14 \u0e19\u0e21\u0e40\u0e1b\u0e23\u0e35\u0e49\u0e22\u0e27 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e19\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 331\/4  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e33\u0e1a\u0e34\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004452\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004452 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e35\u0e27\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 2569-07-07 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 326\/1  \u0e16\u0e19\u0e19\u0e21\u0e13\u0e35\u0e19\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015243\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01 \u0e01\u0e23\u0e35\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015243 \u0e1a\u0e08.\u0e42\u0e01 \u0e01\u0e23\u0e35\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e14\u0e49\u0e32\u0e19\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e44\u0e17\u0e22 \u0e2b\u0e31\u0e15\u0e16\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e14\u0e44\u0e17\u0e22\u0e15\u0e32\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u533b\u7642\u30fb\u798f\u7949 28  \u0e0b\u0e2d\u0e22 7 (\u0e16\u0e19\u0e19\u0e28\u0e34\u0e23\u0e34\u0e21\u0e31\u0e07\u0e04\u0e25\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c) \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015251\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e22\u0e27\u0e19 \u0e40\u0e1f\u0e34\u0e07 26 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015251 \u0e1a\u0e08.\u0e2b\u0e22\u0e27\u0e19 \u0e40\u0e1f\u0e34\u0e07 26 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015278\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e40\u0e17\u0e35\u0e22\u0e19\u0e23\u0e38\u0e48\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015278 \u0e1a\u0e08.\u0e2b\u0e07\u0e40\u0e17\u0e35\u0e22\u0e19\u0e23\u0e38\u0e48\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e2a\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e44\u0e21\u0e49 \u0e42\u0e23\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u88fd\u9020 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48-\u0e2b\u0e32\u0e07\u0e14\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015294\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e0b\u0e35 \u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93299\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93299\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015294 \u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e0b\u0e35 \u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 93299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e40\u0e23\u0e34\u0e07\u0e23\u0e21\u0e13\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u82b8\u8853\u30fb\u5a2f\u697d 71\/1  \u0e16\u0e19\u0e19\u0e28\u0e34\u0e23\u0e34\u0e18\u0e23 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015308\",\"name_th\":\"\u0e1a\u0e08.57 \u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93299\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93299\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015308 \u0e1a\u0e08.57 \u0e04\u0e25\u0e31\u0e1a \u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 93299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u82b8\u8853\u30fb\u5a2f\u697d 43,43\/1  \u0e16\u0e19\u0e19\u0e2d\u0e31\u0e29\u0e0e\u0e32\u0e18\u0e23 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015332\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e39\u0e49\u0e14 \u0e41\u0e1f\u0e04\u0e17\u0e2d\u0e23\u0e35\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015332 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e39\u0e49\u0e14 \u0e41\u0e1f\u0e04\u0e17\u0e2d\u0e23\u0e35\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 321\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e23\u0e2d\u0e1a 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015375\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10761\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10761\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015375 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 10761 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e31\u0e48\u0e27\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e04\u0e31\u0e48\u0e27 \u0e1a\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e07\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e31\u0e48\u0e27\u0e01\u0e32\u0e41\u0e1f \u0e15\u0e39\u0e49\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 249  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001374\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e48\u0e32 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0515569001374 \u0e1a\u0e08.\u0e25\u0e39\u0e21\u0e48\u0e32 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 181\/280  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0545569000751\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e49\u0e32\u0e07\u0e44\u0e17\u0e22\u0e27\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"31001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"31001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000751 \u0e1a\u0e08.\u0e0a\u0e49\u0e32\u0e07\u0e44\u0e17\u0e22\u0e27\u0e39\u0e49\u0e14 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 31001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u88fd\u9020 136  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0545569000769\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e32 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000769 \u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e32 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 338  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0573569002077\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e2d\u0e22\u0e2b\u0e21\u0e2d\u0e01\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10761\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10761\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002077 \u0e2b\u0e08.\u0e14\u0e2d\u0e22\u0e2b\u0e21\u0e2d\u0e01 2569-07-07 1000000 10761 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e32\u0e23\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e41\u0e1f\u0e1a\u0e14 \u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e01\u0e32\u0e41\u0e1f\u0e1c\u0e2a\u0e21\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e04\u0e31\u0e48\u0e27\u0e01\u0e32\u0e41\u0e1f \u88fd\u9020 362  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0573569002085\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e35\u0e23\u0e35 \u0e40\u0e04\u0e35\u0e22\u0e07\u0e14\u0e2d\u0e22\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002085 \u0e2b\u0e08.\u0e04\u0e35\u0e23\u0e35 \u0e40\u0e04\u0e35\u0e22\u0e07\u0e14\u0e2d\u0e22 2569-07-07 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e21\u0e30\u0e04\u0e32\u0e40\u0e14\u0e40\u0e21\u0e35\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 26 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004365\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e21\u0e25 \u0e44\u0e2e\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004365 \u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e21\u0e25 \u0e44\u0e2e\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e1e\u0e37\u0e0a\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0585569000262\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e07\u0e01\u0e38\u0e49\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\",\"province_ja\":\"\u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\",\"search_text\":\"0585569000262 \u0e1a\u0e08.\u0e2b\u0e21\u0e34\u0e07\u0e01\u0e38\u0e49\u0e22 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 128\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e13 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0633569000651\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e08\u0e35 \u0e42\u0e2e\u0e21\u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000651 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e08\u0e35 \u0e42\u0e2e\u0e21\u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 2569-07-07 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 151\/1  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e1e\u0e32\u0e19\u0e34\u0e0a \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0635569001411\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e25\u0e2d\u0e22 \u0e23\u0e31\u0e15\u0e19\u0e28\u0e34\u0e25\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001411 \u0e1a\u0e08. \u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e25\u0e2d\u0e22 \u0e23\u0e31\u0e15\u0e19\u0e28\u0e34\u0e25\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2b\u0e22\u0e01 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e1e\u0e25\u0e2d\u0e22 \u0e2b\u0e34\u0e19\u0e21\u0e35\u0e04\u0e48\u0e32 \u0e2b\u0e34\u0e19\u0e01\u0e36\u0e48\u0e07\u0e21\u0e35\u0e04\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 1212\/89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0653569001053\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e15\u0e38\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001053 \u0e2b\u0e08.\u0e40\u0e01\u0e15\u0e38\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 2569-07-07 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 299  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e30\u0e40\u0e14\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002159\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2a\u0e30\u0e1a\u0e31\u0e14 \u0e44\u0e21\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002159 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2a\u0e30\u0e1a\u0e31\u0e14 \u0e44\u0e21\u0e48  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0673569000529\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2e\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e2d\u0e35\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0673569000529 \u0e2b\u0e08.\u0e40\u0e2e\u0e1f\u0e40\u0e27\u0e48\u0e19 \u0e2d\u0e35\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 2569-07-07 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 379  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003065\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003065 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 1 \u0e16\u0e19\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01-\u0e1a\u0e32\u0e07\u0e41\u0e1e \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003073\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49\u0e1e\u0e32\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003073 \u0e1a\u0e08.\u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49\u0e1e\u0e32\u0e27\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46206 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002484\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e27\u0e22\u0e01\u0e32\u0e0d \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002484 \u0e1a\u0e08.\u0e21\u0e32\u0e2a\u0e27\u0e22\u0e01\u0e32\u0e0d \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32 \u0e0a\u0e38\u0e14\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 155\/3-4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002492\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e17\u0e09\u0e30\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002492 \u0e1a\u0e08.\u0e21\u0e31\u0e17\u0e09\u0e30\u0e01\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 (cafe) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 83\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000609\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e34\u0e19\u0e17\u0e27\u0e35\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000609 \u0e2b\u0e08.\u0e2a\u0e34\u0e19\u0e17\u0e27\u0e35\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-07 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e39\u0e49\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e2a\u0e27\u0e48\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e08\u0e35\u0e22\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e15\u0e39\u0e49\u0e0a\u0e32\u0e23\u0e4c\u0e15\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002042\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17020\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17020\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002042 \u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 17020 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e2d\u0e19\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e2d\u0e19\u0e25\u0e39\u0e01\u0e1f\u0e39\u0e01 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u88fd\u9020 129\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001001\",\"name_th\":\"\u0e2b\u0e08.788 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e21\u0e39\u0e2a\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001001 \u0e2b\u0e08.788 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e21\u0e39\u0e2a\u0e14 2569-07-07 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006838\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e48\u0e32\u0e42\u0e01\u0e23 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006838 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e48\u0e32\u0e42\u0e01\u0e23 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46692 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e2a\u0e21 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e38\u0e4b\u0e22 \u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e37\u0e0a \u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e37\u0e0a \u0e2a\u0e32\u0e23\u0e0a\u0e35\u0e27\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e38\u0e25\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e32\u0e25\u0e32\u0e41\u0e14\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006846\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006846 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e25\u0e21\u0e40\u0e22\u0e47\u0e19  \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e19\u0e49\u0e33\u0e22\u0e32\u0e41\u0e1b\u0e23\u0e1c\u0e31\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 299\/82  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006871\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e2b\u0e25\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006871 \u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e2b\u0e25\u0e35 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006889\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e27\u0e22 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006889 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e27\u0e22 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 56\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007117\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e07\u0e28\u0e4c\u0e20\u0e32 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007117 \u0e1a\u0e08.\u0e1e\u0e07\u0e28\u0e4c\u0e20\u0e32 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u4e0d\u52d5\u7523 923\/4 \u0e02  \u0e16\u0e19\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0765569001437\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e18\u0e32\u0e23\u0e32 \u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001437 \u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e18\u0e32\u0e23\u0e32 \u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 375\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569002883\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e40\u0e0a\u0e2d\u0e2d\u0e23\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002883 \u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e40\u0e0a\u0e2d\u0e2d\u0e23\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 68201 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 555\/23  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e0b\u0e34\u0e15\u0e35\u0e49 88\/1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002581\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e27\u0e0d\u0e41\u0e04\u0e21\u0e1b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002581 \u0e1a\u0e08.\u0e08\u0e27\u0e0d\u0e41\u0e04\u0e21\u0e1b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 199\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0813569000438\",\"name_th\":\"\u0e2b\u0e08.\u0e2e\u0e2d\u0e27\u0e4c\u0e04 \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e1b\u0e44\u0e25\u0e19\u0e4c \u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0813569000438 \u0e2b\u0e08.\u0e2e\u0e2d\u0e27\u0e4c\u0e04 \u0e41\u0e2d\u0e14\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e1b\u0e44\u0e25\u0e19\u0e4c \u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 2569-07-07 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e01\u0e35\u0e2c\u0e32\u0e1c\u0e08\u0e0d\u0e20\u0e31\u0e22 \u0e42\u0e2b\u0e19\u0e2a\u0e25\u0e34\u0e07 \u0e40\u0e14\u0e34\u0e19\u0e1b\u0e48\u0e32 \u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 580  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0815569002025\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c \u0e40\u0e0b\u0e40\u0e23\u0e19\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002025 \u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c \u0e40\u0e0b\u0e40\u0e23\u0e19\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0825569001100\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001100 \u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 25\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0833569000543\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e40\u0e1e\u0e23\u0e2a\u0e17\u0e35\u0e08 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0833569000543 \u0e2b\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e40\u0e1e\u0e23\u0e2a\u0e17\u0e35\u0e08 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-07 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 45\/164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012543\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e07\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012543 \u0e1a\u0e08.\u0e2b\u0e25\u0e07\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102\/139  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 15 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012560\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012560 \u0e1a\u0e08.\u0e27\u0e35\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/205  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010109\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e40\u0e2d\u0e42\u0e19\u0e30\u0e01\u0e34\u0e27 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010109 \u0e1a\u0e08.\u0e2d\u0e38\u0e40\u0e2d\u0e42\u0e19\u0e30\u0e01\u0e34\u0e27 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 , \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e34\u0e49\u0e07\u0e22\u0e48\u0e32\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 7\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010117\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35.\u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e25\u0e19\u0e14\u0e4c\u0e2a\u0e40\u0e04\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010117 \u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35.\u0e04\u0e2d\u0e19\u0e2a\u0e17\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e25\u0e19\u0e14\u0e4c\u0e2a\u0e40\u0e04\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 19\/93  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0855569000502\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e44\u0e19\u0e19\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46611\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46611\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30ce\u30fc\u30f3\u770c\",\"search_text\":\"0855569000502 \u0e1a\u0e08.\u0e27\u0e35\u0e44\u0e19\u0e19\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46611 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e16\u0e48\u0e32\u0e19\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 301\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e19\u0e2d\u0e07 \u30e9\u30ce\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569005384\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005384 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/5  \u0e16\u0e19\u0e19\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005406\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e19\u0e39\u0e23 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005406 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e19\u0e39\u0e23 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 40   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 103 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 41\/5 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005414\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e1a\u0e04\u0e2d\u0e19 \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005414 \u0e1a\u0e08.\u0e23\u0e34\u0e1a\u0e04\u0e2d\u0e19 \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 138  \u0e16\u0e19\u0e19\u0e21\u0e07\u0e04\u0e25\u0e1b\u0e23\u0e30\u0e0a\u0e32 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569000960\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e0e\u0e1b\u0e01\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569000960 \u0e1a\u0e08.\u0e19\u0e31\u0e0e\u0e1b\u0e01\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0935569000765\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000765 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21, \u0e23\u0e30\u0e1a\u0e1a fiber optic,\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32,\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e41\u0e25\u0e30 ev charger, \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32,\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14,\u0e23\u0e30\u0e1a\u0e1a lan \u0e41\u0e25\u0e30\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e40\u0e2a\u0e32\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u5efa\u8a2d 142\/98  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0935569000773\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e42\u0e23\u0e08\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000773 \u0e1a\u0e08.\u0e2a\u0e32\u0e21\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e42\u0e23\u0e08\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e27\u0e2a\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0935569000781\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d \u0e42\u0e23\u0e08\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000781 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d \u0e42\u0e23\u0e08\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e25\u0e34\u0e1b\u0e2a\u0e15\u0e34\u0e01 \u0e1a\u0e25\u0e31\u0e0a\u0e2d\u0e2d\u0e19 \u0e2d\u0e32\u0e22\u0e44\u0e25\u0e19\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e0b\u0e23\u0e31\u0e48\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e23\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19 \u0e04\u0e23\u0e35\u0e21\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14 \u0e02\u0e19\u0e15\u0e32\u0e1b\u0e25\u0e2d\u0e21 \u0e14\u0e34\u0e19\u0e2a\u0e2d\u0e40\u0e02\u0e35\u0e22\u0e19\u0e04\u0e34\u0e49\u0e27 \u0e04\u0e23\u0e35\u0e21\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e2a\u0e1a\u0e39\u0e48 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 215  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0955569000552\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e42\u0e15\u0e0b\u0e48\u0e32 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000552 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e42\u0e15\u0e0b\u0e48\u0e32 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e07\u0e08\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33  \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e42\u0e23\u0e23\u0e2a 10 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569006939\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e31\u0e0a\u0e0a\u0e32 1983\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006939 \u0e2b\u0e08.\u0e19\u0e31\u0e0a\u0e0a\u0e32 1983 2569-07-06 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 48\/152  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 111 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006947\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e35\u0e19\u0e42\u0e19\u0e27\u0e32 2026\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006947 \u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e35\u0e19\u0e42\u0e19\u0e27\u0e32 2026 2569-07-06 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 98\/196  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 73\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006955\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04 \u0e2a\u0e40\u0e1b\u0e0b 89\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006955 \u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e17\u0e04 \u0e2a\u0e40\u0e1b\u0e0b 89 2569-07-06 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 21\/81  \u0e16\u0e19\u0e19\u0e17\u0e2b\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006971\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e31\u0e25\u0e23\u0e14\u0e32 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006971 \u0e2b\u0e08.\u0e01\u0e31\u0e25\u0e23\u0e14\u0e32 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 99\/24  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e35\u0e0a \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006980\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e0a\u0e15999\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006980 \u0e2b\u0e08.\u0e23\u0e0a\u0e15999 2569-07-06 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e2d\u0e23\u0e4c \u0e2a\u0e35 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e23\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 924  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e32\u0e19\u0e19\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006998\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e35\u0e42\u0e2d\u0e1f\u0e32\u0e40\u0e0b\u0e47\u0e15 \u0e2d\u0e30\u0e42\u0e01\u0e23\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006998 \u0e2b\u0e08.\u0e19\u0e35\u0e42\u0e2d\u0e1f\u0e32\u0e40\u0e0b\u0e47\u0e15 \u0e2d\u0e30\u0e42\u0e01\u0e23 2569-07-06 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 416\/24  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e21\u0e27\u0e34\u0e17 77 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007005\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e0b\u0e35 \u0e1e\u0e23\u0e4a\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 2026\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007005 \u0e2b\u0e08.\u0e0b\u0e35\u0e0b\u0e35 \u0e1e\u0e23\u0e4a\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 2026 2569-07-06 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e43\u0e0a\u0e49 \u0e42\u0e2d\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d \u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 571\/36  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e34 \u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e49\u0e19 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 83 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126812\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e32\u0e21\u0e17\u0e32\u0e40\u0e25\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126812 \u0e1a\u0e08.\u0e21\u0e32\u0e14\u0e32\u0e21\u0e17\u0e32\u0e40\u0e25\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 164 \u0e41\u0e22\u0e01 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126821\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e20\u0e31\u0e17\u0e23 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126821 \u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e20\u0e31\u0e17\u0e23 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 (work permit) \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 (visa) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e21\u0e35\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 32\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e0a\u0e48\u0e32\u0e07\u0e40\u0e15\u0e35\u0e49\u0e22 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e33\u0e23\u0e32\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126839\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e23\u0e2a\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126839 \u0e1a\u0e08.\u0e40\u0e1e\u0e23\u0e2a\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e01\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e01\u0e04\u0e34\u0e27 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19         \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e39\u0e19\u0e28\u0e34\u0e23\u0e342 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 3 \u0e41\u0e22\u0e01 5 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126847\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e01\u0e0b\u0e4c \u0e23\u0e35\u0e41\u0e27\u0e25\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126847 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e01\u0e0b\u0e4c \u0e23\u0e35\u0e41\u0e27\u0e25\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46695 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e37\u0e2d 2 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 4 \u0e0b\u0e2d\u0e22 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126855\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 69 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126855 \u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 69 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u4e0d\u52d5\u7523 156  \u0e16\u0e19\u0e19\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22\u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126871\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e38\u0e21\u0e32\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126871 \u0e1a\u0e08.\u0e21\u0e38\u0e21\u0e32\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 59112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e33\u0e01\u0e31\u0e1a \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e25\u0e30\u0e04\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 28\/30  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e42\u0e21\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 45\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126880\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126880 \u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence: ai)  \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai security) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c (cybersecurity) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e20\u0e31\u0e22\u0e04\u0e38\u0e01\u0e04\u0e32\u0e21\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 (cyber threat intelligence) \u0e01\u0e32\u0e23\u0e44\u0e25\u0e48\u0e25\u0e48\u0e32\u0e20\u0e31\u0e22\u0e04\u0e38\u0e01\u0e04\u0e32\u0e21\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c (threat hunting)  \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e1d\u0e49\u0e32\u0e23\u0e30\u0e27\u0e31\u0e07\u0e20\u0e31\u0e22\u0e04\u0e38\u0e01\u0e04\u0e32\u0e21\u0e17\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 (big data)  \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 50  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e07\u0e29\u0e4c 1 (\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07 6 \u0e27\u0e32) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126901\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e34\u0e21\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126901 \u0e1a\u0e08.\u0e09\u0e34\u0e21\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e23\u0e32\u0e22\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e09\u0e25\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e21\u0e1a\u0e31\u0e15\u0e23          \u0e41\u0e1c\u0e48\u0e19\u0e1e\u0e31\u0e1a \u0e42\u0e1a\u0e23\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e07\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e25\u0e30 \u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14          \u0e42\u0e14\u0e22\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e04\u0e21\u0e0a\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u88fd\u9020 298\/62  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e34 \u0e42\u0e2d\u0e42\u0e0b\u0e19 \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 53 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126928\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35 \u0e2d\u0e35\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10504\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10504\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126928 \u0e1a\u0e08.\u0e40\u0e04\u0e0b\u0e35 \u0e2d\u0e35\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 10504 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 69\/4  \u0e0b\u0e2d\u0e22 \u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c18 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126936\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e25 \u0e1f\u0e25\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43303\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43303\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126936 \u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e25 \u0e1f\u0e25\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 43303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e32\u0e2a\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 53\/1  \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 64 \u0e16\u0e19\u0e19\u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126961\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e14\u0e23\u0e35\u0e19\u0e32\u0e25\u0e35\u0e19 89 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126961 \u0e1a\u0e08.\u0e2d\u0e30\u0e14\u0e23\u0e35\u0e19\u0e32\u0e25\u0e35\u0e19 89 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 73101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e19\u0e31\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e43\u0e19\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 212\/9  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126979\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e35\u0e19\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126979 \u0e1a\u0e08.\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19 \u0e01\u0e23\u0e35\u0e19\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 \u0e2a\u0e19\u0e32\u0e21\u0e2b\u0e0d\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 423  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126995\",\"name_th\":\"\u0e1a\u0e08.\u0e2a.\u0e23\u0e32\u0e0a\u0e40\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126995 \u0e1a\u0e08.\u0e2a.\u0e23\u0e32\u0e0a\u0e40\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e16\u0e19\u0e2d\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e21\u0e39\u0e1d\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e2b\u0e21\u0e39\u0e2b\u0e22\u0e2d\u0e07 \u0e01\u0e38\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 286\/41  \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e02\u0e27\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127002\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 \u0e40\u0e04\u0e1e\u0e23\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32902\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32902\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127002 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e21\u0e01\u0e49\u0e32 \u0e40\u0e04\u0e1e\u0e23\u0e34\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 32902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e1f\u0e40\u0e0b\u0e17 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2a\u0e15\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e41\u0e04\u0e15\u0e15\u0e32\u0e25\u0e47\u0e2d\u0e04 \u0e42\u0e1a\u0e23\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e41\u0e1a\u0e1a\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e19\u0e32\u0e21\u0e1a\u0e31\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e34\u0e25 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e07\u0e15\u0e31\u0e27\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 3601\/366 \u0e15\u0e23\u0e2d\u0e01\u0e19\u0e2d\u0e01\u0e40\u0e02\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127011\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127011 \u0e1a\u0e08.\u0e04\u0e39\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e27\u0e30 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 254\/248  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 112 \u0e16\u0e19\u0e19- \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127029\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e21\u0e19 \u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e21\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127029 \u0e1a\u0e08.\u0e18\u0e21\u0e19 \u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e21\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e41\u0e25\u0e30\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u533b\u7642\u30fb\u798f\u7949 9  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 17 \u0e41\u0e22\u0e01 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127045\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e21-\u0e19\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127045 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e19\u0e2a\u0e21-\u0e19\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e21\u0e49\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6004\/187  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127061\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e15\u0e32 \u0e2b\u0e39 \u0e04\u0e2d \u0e08\u0e21\u0e39\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127061 \u0e1a\u0e08.\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e15\u0e32 \u0e2b\u0e39 \u0e04\u0e2d \u0e08\u0e21\u0e39\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e15\u0e32 \u0e2b\u0e39 \u0e04\u0e2d \u0e08\u0e21\u0e39\u0e01 \u0e41\u0e25\u0e30\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e32\u0e23 \u0e15\u0e32 \u0e2b\u0e39 \u0e04\u0e2d \u0e08\u0e21\u0e39\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u533b\u7642\u30fb\u798f\u7949 8  \u0e16\u0e19\u0e19\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\u0e23\u0e32\u0e0a\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127070\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20293\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20293\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127070 \u0e1a\u0e08.\u0e04\u0e34\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 20293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e49\u0e32\u0e19\u0e44\u0e21\u0e49\u0e2b\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 (reed diffuser) \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2a\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 989\/20  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 the elegance \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 81 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127088\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e42\u0e27\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127088 \u0e1a\u0e08.\u0e42\u0e19\u0e42\u0e27\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e1e\u0e25\u0e17 \u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e07\u0e32\u0e19\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 2823\/3   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2020 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127126\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e0a\u0e0d\u0e32\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127126 \u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e0a\u0e0d\u0e32\u0e01\u0e32\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23  \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e33\u0e04\u0e14\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e2a\u0e37\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35  \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2b\u0e19\u0e35\u0e49\u0e2a\u0e34\u0e19  \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a  \u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e35\u0e49\u0e07\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 30  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 5 \u0e41\u0e22\u0e01 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127134\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e31\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e27\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127134 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e31\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e27\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e40\u0e01\u0e49\u0e3262 (\u0e0b\u0e2d\u0e229 \u0e40\u0e2a\u0e23\u0e358) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127151\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35 \u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127151 \u0e1a\u0e08.\u0e40\u0e2d\u0e1a\u0e35 \u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 3  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a16 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127169\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e1f\u0e39\u0e4a\u0e14 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127169 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e1f\u0e39\u0e4a\u0e14 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 34\/4  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e193\u0e0b\u0e2d\u0e2212 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127185\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127185 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0a\u0e32 \u0e1c\u0e07\u0e0a\u0e32\u0e40\u0e02\u0e35\u0e22\u0e27\u0e21\u0e31\u0e17\u0e09\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 590\/3  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 70\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127193\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e01) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127193 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e01) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e0b\u0e48\u0e2d\u0e21 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e27\u0e14\u0e04\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e1a\u0e32\u0e30\u0e19\u0e27\u0e14\u0e2b\u0e25\u0e31\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e25\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e32\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e27\u0e14\u0e40\u0e17\u0e49\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e48\u0e19\u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e37\u0e19\u0e19\u0e27\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e19\u0e27\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e21\u0e35\u0e40\u0e1a\u0e32\u0e30\u0e19\u0e31\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e1e\u0e34\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e48\u0e19 \u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e21\u0e31\u0e25\u0e25\u0e34\u0e15\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/393  \u0e16\u0e19\u0e19\u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127223\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59203\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59203\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127223 \u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 59203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e1e\u0e25\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e23\u0e49\u0e2d\u0e07 \u0e17\u0e33\u0e19\u0e2d\u0e07 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e32\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e42\u0e19\u0e49\u0e15\u0e40\u0e1e\u0e25\u0e07 \u0e23\u0e27\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 8\/85  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 85 \u0e41\u0e22\u0e01 2-5 \u0e16\u0e19\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127240\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e352 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127240 \u0e1a\u0e08.\u0e17\u0e352 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e25\u0e30\u0e04\u0e23\u0e40\u0e27\u0e17\u0e35 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e25\u0e30\u0e04\u0e23 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e35\u0e2c\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 8\/357  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127258\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25\u0e40\u0e25\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127258 \u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25\u0e40\u0e25\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e08\u0e32\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 2\/206  \u0e0b\u0e2d\u0e22 \u0e44\u0e21\u0e15\u0e23\u0e35\u0e08\u0e34\u0e15 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127266\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e0a\u0e2d\u0e22\u0e0b\u0e4c \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127266 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e0a\u0e2d\u0e22\u0e0b\u0e4c \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 1214  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 87 (\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127282\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e04\u0e23\u0e2d\u0e2a\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e21\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127282 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e04\u0e23\u0e2d\u0e2a\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e21\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 890\/1  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127304\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127304 \u0e1a\u0e08.\u0e40\u0e08\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 123\/23  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127312\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e15\u0e23\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46592\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46592\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127312 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e15\u0e23\u0e35 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46592 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/54  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c 3 \u0e41\u0e22\u0e01 8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127321\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e1e\u0e35 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127321 \u0e1a\u0e08.\u0e1e\u0e35\u0e17\u0e35\u0e1e\u0e35 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e07\u0e08\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5efa\u8a2d 70\/133  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 30 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127339\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e34\u0e2a\u0e1f\u0e39\u0e25 \u0e40\u0e2e\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55909\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55909\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127339 \u0e1a\u0e08.\u0e1a\u0e25\u0e34\u0e2a\u0e1f\u0e39\u0e25 \u0e40\u0e2e\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 55909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e0b\u0e36\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e14\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 595\/13-14  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127363\",\"name_th\":\"\u0e1a\u0e08.59 \u0e20\u0e39\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e25\u0e2d\u0e27\u0e4c \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127363 \u0e1a\u0e08.59 \u0e20\u0e39\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e25\u0e2d\u0e27\u0e4c \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 152  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 30-01 \u0e22\u0e39\u0e19\u0e34\u0e15 3017 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127371\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1b\u0e42\u0e25\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127371 \u0e1a\u0e08.\u0e44\u0e1b\u0e42\u0e25\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 79110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e1a\u0e31\u0e15\u0e23\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 77\/29  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04 \u0e21\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19-\u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e16\u0e19\u0e19\u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127398\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e1b\u0e21\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19 \u0e2d\u0e34\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e0b\u0e35\u0e1f \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93293\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93293\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127398 \u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e1b\u0e21\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19 \u0e2d\u0e34\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e0b\u0e35\u0e1f \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 93293 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e27\u0e19\u0e2a\u0e19\u0e38\u0e01 vr (virtual reality) \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e30\u0e2a\u0e21 (art toys) \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e01\u0e21 vr \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e40\u0e2b\u0e47\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e23\u0e30\u0e1a\u0e1a vr \u82b8\u8853\u30fb\u5a2f\u697d 51  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e21\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 - \u0e23\u0e32\u0e21\u0e04\u0e33\u0e40\u0e40\u0e2b\u0e07  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 6 - 7 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127401\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127401 \u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 64202 \u0e40\u0e02\u0e49\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar) \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u91d1\u878d\u30fb\u4fdd\u967a 33\/36  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e2d\u0e25\u0e25\u0e4c\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127436\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127436 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e17\u0e33 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e1a\u0e32\u0e19\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19 \u0e1a\u0e32\u0e19\u0e2a\u0e27\u0e34\u0e07 \u0e19\u0e32\u0e19\u0e01\u0e23\u0e30\u0e17\u0e38\u0e49\u0e07  \u0e19\u0e32\u0e19\u0e40\u0e1f\u0e35\u0e49\u0e22\u0e21 \u0e01\u0e31\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e2a\u0e01\u0e32\u0e22\u0e44\u0e25\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5efa\u8a2d 23\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127479\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e15\u0e34\u0e14\u0e08\u0e23\u0e27\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127479 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e15\u0e34\u0e14\u0e08\u0e23\u0e27\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/149  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e19\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e2e\u0e21 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5  \u0e0b\u0e2d\u0e22 82 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127517\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e42\u0e25\u0e27\u0e4c \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55109\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55109\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127517 \u0e1a\u0e08.\u0e2a\u0e42\u0e25\u0e27\u0e4c \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 55109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 38  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e14\u0e39\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127525\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e04\u0e42\u0e17\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127525 \u0e1a\u0e08.\u0e2d\u0e2d\u0e04\u0e42\u0e17\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 74109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e2a\u0e37\u0e48\u0e2d \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30 \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 420  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 53 (\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e28\u0e23\u0e35\u0e0a\u0e27\u0e32\u0e25\u0e32) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127568\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e21\u0e04\u0e2d\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e14 \u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127568 \u0e1a\u0e08.\u0e44\u0e21\u0e04\u0e2d\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e14 \u0e2a\u0e22\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0a\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e41\u0e17\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 986  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127576\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e19\u0e34\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127576 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e19\u0e34\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e23\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1042\/118  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127584\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e23\u0e35\u0e42\u0e0b\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127584 \u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e23\u0e35\u0e42\u0e0b\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e35\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e08\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23 \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 30\/28  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002224\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (2025)\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002224 \u0e2b\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (2025) 2569-07-06 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 66\/3  \u0e0b\u0e2d\u0e22 3 (\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e38\u0e25) \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e25\u0e27\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022171\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022171 \u0e1a\u0e08.\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022197\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022197 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 189\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022219\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e1f\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022219 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e1f\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u4e0d\u52d5\u7523 89\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022235\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01 \u0e40\u0e14\u0e40\u0e27\u0e25\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022235 \u0e1a\u0e08.\u0e42\u0e01 \u0e40\u0e14\u0e40\u0e27\u0e25\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 78\/460  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022243\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e04 \u0e0b\u0e39\u0e1e\u0e23\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47911\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47911\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022243 \u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e04 \u0e0b\u0e39\u0e1e\u0e23\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47911 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 885\/73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022260\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e40\u0e27\u0e23\u0e48\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022260 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e40\u0e27\u0e23\u0e48\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 334\/69  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e3262 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e20\u0e31\u0e17\u0e2a\u0e2328 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e32\u0e21\u0e41\u0e14\u0e07 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022316\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022316 \u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 1580  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022332\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022332 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e2a\u0e15\u0e35\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e23\u0e31\u0e14\u0e17\u0e48\u0e2d \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/225  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002119\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e01\u0e32\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002119 \u0e2b\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e01\u0e32\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-06 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 73\/941  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e42\u0e2e\u0e21\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025048\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e47\u0e19\u0e40\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025048 \u0e1a\u0e08.\u0e40\u0e14\u0e47\u0e19\u0e40\u0e17\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u533b\u7642\u30fb\u798f\u7949 111\/257  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025056\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e25\u0e1f\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025056 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e25\u0e1f\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e14 \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e35\u0e49 (shopee), \u0e15\u0e34\u0e4a\u0e01\u0e15\u0e4a\u0e2d\u0e01 (tiktok), \u0e25\u0e32\u0e0b\u0e32\u0e14\u0e49\u0e32 (lazada), \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e01 (facebook), \u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e32\u0e41\u0e01\u0e23\u0e21 (instagram), \u0e22\u0e39\u0e17\u0e39\u0e1b (youtube), \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 77\/20-21  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04 41 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025064\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025064 \u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 159\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025072\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e04\u0e4c\u0e42\u0e25\u0e08\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025072 \u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e04\u0e4c\u0e42\u0e25\u0e08\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e02\u0e22\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e07\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u88fd\u9020 97\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e42\u0e22\u0e18\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025099\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e04.\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e32\u0e2a \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c  \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025099 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e04.\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e32\u0e2a \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c  \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 82990 \u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e41\u0e1b\u0e25\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 3\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025102\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e49\u0e14 \u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025102 \u0e1a\u0e08.\u0e0b\u0e39\u0e49\u0e14 \u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c (franchise) \u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 12\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025129\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025129 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e44\u0e01\u0e25 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (cctv) \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (lan) \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e2d\u0e2d\u0e1f\u0e15\u0e34\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e21\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (automation) \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e44\u0e2b\u0e21\u0e49 (fire alarm) \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 22\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025145\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e18\u0e34 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025145 \u0e1a\u0e08.\u0e2d\u0e18\u0e34 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 chatbot \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 api \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u60c5\u5831\u901a\u4fe1\u30fbit 222\/11  \u0e16\u0e19\u0e19\u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025170\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025170 \u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e1e\u0e23 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 107\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025188\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2e\u0e2d\u0e25\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025188 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2e\u0e2d\u0e25\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 160\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025196\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e34\u0e21\u0e25\u0e32\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025196 \u0e1a\u0e08.\u0e15\u0e34\u0e21\u0e25\u0e32\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04  \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u88fd\u9020 88\/289  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002232\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e0b\u0e25\u0e35\u0e19 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002232 \u0e2b\u0e08.\u0e40\u0e0b\u0e25\u0e35\u0e19 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-06 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 99\/327  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e17\u0e23\u0e31\u0e2a\u0e15\u0e4c\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002241\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e21\u0e19\u0e35\u0e48 \u0e0a\u0e47\u0e2d\u0e1b \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002241 \u0e2b\u0e08.\u0e40\u0e21\u0e19\u0e35\u0e48 \u0e0a\u0e47\u0e2d\u0e1b \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-06 1000000 47114 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002259\",\"name_th\":\"\u0e2b\u0e08.\u0e1b.\u0e42\u0e20\u0e0a\u0e19\u0e32\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002259 \u0e2b\u0e08.\u0e1b.\u0e42\u0e20\u0e0a\u0e19\u0e32 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 90\/153-154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020682\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e22\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020682 \u0e1a\u0e08.\u0e14\u0e2d\u0e22\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/4  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e21\u0e32\u0e23\u0e27\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020691\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e17\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020691 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e17\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/612  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e23\u0e32\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19-\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020712\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e35 \u0e1e\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020712 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e27\u0e35 \u0e1e\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 21001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u88fd\u9020 111\/318  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020721\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e40\u0e2d\u0e2a \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020721 \u0e1a\u0e08.\u0e1e\u0e35 \u0e40\u0e2d\u0e2a \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 43210 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e1a\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e19\u0e40\u0e2a\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e15\u0e32\u0e21\u0e16\u0e19\u0e19\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19 \u0e15\u0e32\u0e21\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e02\u0e32\u0e22 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u5efa\u8a2d 24\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020739\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e32\u0e21\u0e32\u0e22 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020739 \u0e1a\u0e08.\u0e40\u0e21\u0e32\u0e21\u0e32\u0e22 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e0a\u0e27\u0e4c\u0e23\u0e39\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e14 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u5bbf\u6cca\u30fb\u98f2\u98df 93\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020747\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e44\u0e1f\u0e19\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020747 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e44\u0e1f\u0e19\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020755\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e49\u0e2d\u0e0b\u0e0b\u0e4c \u0e42\u0e04\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020755 \u0e1a\u0e08.\u0e04\u0e23\u0e49\u0e2d\u0e0b\u0e0b\u0e4c \u0e42\u0e04\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (software as a service) \u60c5\u5831\u901a\u4fe1\u30fbit 99\/44  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e2d\u0e25\u0e35\u0e1f \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e04\u0e25\u0e2d\u0e07 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020763\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020763 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e14\u0e34\u0e1a \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e42\u0e25\u0e2b\u0e30\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e22\u0e36\u0e14\u0e40\u0e2b\u0e19\u0e35\u0e48\u0e22\u0e27 \u0e19\u0e4a\u0e2d\u0e15 \u0e2a\u0e01\u0e23\u0e39 \u0e2a\u0e25\u0e31\u0e01\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/232  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48\u0e17\u0e32\u0e27\u0e19\u0e4c\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32-\u0e04\u0e25\u0e2d\u0e075 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e0b\u0e2d\u0e22 16 \u0e16\u0e19\u0e19\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32-\u0e04\u0e25\u0e2d\u0e075 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020771\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e04\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020771 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e04\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 137\/79-80  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020780\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e19\u0e35\u0e48\u0e2e\u0e31\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020780 \u0e1a\u0e08.\u0e44\u0e17\u0e19\u0e35\u0e48\u0e2e\u0e31\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 10801 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e2d\u0e47\u0e01\u0e42\u0e0b\u0e15\u0e34\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 107\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020798\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e34\u0e19 \u0e18\u0e35\u0e42\u0e2d\u0e23\u0e35 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020798 \u0e1a\u0e08.\u0e2a\u0e01\u0e34\u0e19 \u0e18\u0e35\u0e42\u0e2d\u0e23\u0e35 \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 (\u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01)  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01 \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/646  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020801\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020801 \u0e1a\u0e08.\u0e40\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u5efa\u8a2d 51\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020810\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e2d\u0e22 89 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020810 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e2d\u0e22 89 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/27-5\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0143569001139\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e17\u0e1e\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e27\u0e31\u0e19\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28219\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28219\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001139 \u0e2b\u0e08.\u0e40\u0e17\u0e1e\u0e1e\u0e23\u0e30\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2d\u0e2d\u0e25 \u0e2d\u0e34\u0e19 \u0e27\u0e31\u0e19 2569-07-06 1000000 28219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 101\/146  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004415\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e47\u0e2d\u0e04\u0e01\u0e35\u0e49 \u0e1b\u0e4a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004415 \u0e1a\u0e08.\u0e0b\u0e47\u0e2d\u0e04\u0e01\u0e35\u0e49 \u0e1b\u0e4a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004423\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35 \u0e40\u0e2d\u0e2a \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004423 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35 \u0e40\u0e2d\u0e2a \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0155569000550\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e0a\u0e32\u0e42\u0e15\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000550 \u0e1a\u0e08.\u0e04\u0e0a\u0e32\u0e42\u0e15\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e27\u0e1e\u0e31\u0e19\u0e18\u0e4c 2 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0163569000531\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07888\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000531 \u0e2b\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07888\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-06 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001505\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e32 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001505 \u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e32 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 181  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0175569000428\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e1a\u0e34\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000428 \u0e1a\u0e08.\u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e1a\u0e34\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 65\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0175569000436\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e34\u0e04 \u0e2d\u0e30\u0e40\u0e01\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000436 \u0e1a\u0e08.\u0e0a\u0e34\u0e04 \u0e2d\u0e30\u0e40\u0e01\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34 \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002471\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e04 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002471 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e04 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 118  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0202569000041\",\"name_th\":\"\u0e2b\u0e2a.\u0e41\u0e1f\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0202569000041 \u0e2b\u0e2a.\u0e41\u0e1f\u0e23\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-06 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 399\/679  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e0b\u0e34\u0e15\u0e35\u0e492 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002827\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42202\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42202\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002827 \u0e2b\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 2569-07-06 1000000 42202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e2a\u0e32\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u5efa\u8a2d 123\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035450\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e47\u0e01\u0e0b\u0e2d\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035450 \u0e1a\u0e08.\u0e40\u0e27\u0e47\u0e01\u0e0b\u0e2d\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 22220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 83\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035468\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e07\u0e44\u0e17\u0e48 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035468 \u0e1a\u0e08.\u0e08\u0e07\u0e44\u0e17\u0e48 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/716  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035476\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035476 \u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22\u0e08\u0e32\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 260\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035484\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19\u0e08\u0e39\u0e15\u0e34\u0e48\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035484 \u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19\u0e08\u0e39\u0e15\u0e34\u0e48\u0e07 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e41\u0e1a\u0e04\u0e42\u0e2e \u0e23\u0e16\u0e15\u0e31\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 27\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035514\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035514 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e25\u0e34\u0e07\u0e04\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e44\u0e14\u0e04\u0e32\u0e2a\u0e15\u0e34\u0e49\u0e07 (\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e2a\u0e39\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 133\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035549\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035549 \u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e08\u0e39\u0e19 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u5bbf\u6cca\u30fb\u98f2\u98df 293\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035573\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e31\u0e01\u0e0b\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e35 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035573 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e25\u0e31\u0e01\u0e0b\u0e4c\u0e0a\u0e31\u0e27\u0e23\u0e35 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e23\u0e16 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25 \u904b\u8f38\u30fb\u7269\u6d41 299\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035581\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e2e\u0e1f\u0e27\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035581 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e2e\u0e1f\u0e27\u0e4c \u0e1e\u0e31\u0e17\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e2d\u0e30\u0e42\u0e01\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e32 \u0e22\u0e32\u0e2a\u0e39\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 98\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035603\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e19\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035603 \u0e1a\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e19\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 3\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035620\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e0b\u0e35 \u0e23\u0e35\u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38300\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38300\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035620 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e0b\u0e35 \u0e23\u0e35\u0e27\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 38300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u0e40\u0e28\u0e29\u0e44\u0e21\u0e49 \u0e44\u0e21\u0e49\u0e40\u0e01\u0e48\u0e32 \u0e1e\u0e32\u0e40\u0e25\u0e17\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e14\u0e49 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 126\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008967\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e34\u0e0a\u0e0a\u0e32\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008967 \u0e1a\u0e08.\u0e13\u0e34\u0e0a\u0e0a\u0e32\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 50\/112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008975\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e0a\u0e49\u0e2d\u0e22\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008975 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14 \u0e0a\u0e49\u0e2d\u0e22\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 80\/111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008983\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0215569008983 \u0e1a\u0e08.\u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49 \u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e42\u0e14\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e1a\u0e1c\u0e49\u0e32\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 234\/533  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003639\",\"name_th\":\"\u0e1a\u0e08.\u0e01.\u0e01\u0e34\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003639 \u0e1a\u0e08.\u0e01.\u0e01\u0e34\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 54\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0303569002575\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e1e\u0e07\u0e28\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002575 \u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e1e\u0e07\u0e28\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-06 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 456\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006980\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\u0e1f\u0e34\u0e2a\u0e34\u0e42\u0e2d\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86902\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86902\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006980 \u0e1a\u0e08.\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\u0e1f\u0e34\u0e2a\u0e34\u0e42\u0e2d\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 86902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27) \u533b\u7642\u30fb\u798f\u7949 1040\/34  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e2e\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e27\u0e34\u0e25\u0e25\u0e4c - \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e22\u0e2d\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006998\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e42\u0e01\u0e4b\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006998 \u0e1a\u0e08.\u0e0a\u0e48\u0e32\u0e07\u0e42\u0e01\u0e4b\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 43210 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 222  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001830\",\"name_th\":\"\u0e1a\u0e08.\u0e0d\u0e32\u0e19\u0e34\u0e2a\u0e17\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001830 \u0e1a\u0e08.\u0e0d\u0e32\u0e19\u0e34\u0e2a\u0e17\u0e4c \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e19\u0e33\u0e17\u0e35\u0e48\u0e22\u0e27\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0b\u0e36\u0e48\u0e07\u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e22\u0e42\u0e14\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07    \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e32\u0e08\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21 \u0e1e\u0e34\u0e1e\u0e34\u0e18\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u0e14\u0e19\u0e15\u0e23\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e04\u0e19\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e2e\u0e31\u0e08\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2e\u0e38\u0e21\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 239  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0323569000530\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e34\u0e23\u0e32\u0e1e\u0e23 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000530 \u0e2b\u0e08.\u0e08\u0e34\u0e23\u0e32\u0e1e\u0e23 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-06 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e31\u0e01 \u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0325569001155\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e17\u0e2d\u0e07\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001155 \u0e1a\u0e08.\u0e14\u0e35\u0e17\u0e2d\u0e07\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0325569001163\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e28\u0e23\u0e35\u0e21\u0e07\u0e04\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001163 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e28\u0e23\u0e35\u0e21\u0e07\u0e04\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46900 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0345569003026\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e21\u0e32\u0e19 \u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003026 \u0e1a\u0e08.\u0e23\u0e35\u0e21\u0e32\u0e19 \u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e16\u0e19\u0e19\u0e19\u0e1e\u0e04\u0e38\u0e13 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0345569003042\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e44\u0e1e\u0e1e\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003042 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e44\u0e1e\u0e1e\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0353569000467\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e1f.\u0e40\u0e2d. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000467 \u0e2b\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e1f.\u0e40\u0e2d. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-06 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e14\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e07\u0e32\u0e19\u0e02\u0e38\u0e14 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e14\u0e34\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 185  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e33\u0e2b\u0e19\u0e2d\u0e07\u0e22\u0e32\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0355569000388\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0355569000388 \u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e32\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2a\u0e27\u0e48\u0e32\u0e19 \u0e04\u0e49\u0e2d\u0e19 \u0e1b\u0e23\u0e30\u0e41\u0e08  \u0e15\u0e25\u0e31\u0e1a\u0e40\u0e21\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e44\u0e23\u0e49\u0e2a\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569002957\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e39\u0e25\u0e4c\u0e1f\u0e40\u0e21\u0e04 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0b\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002957 \u0e2b\u0e08.\u0e27\u0e39\u0e25\u0e4c\u0e1f\u0e40\u0e21\u0e04 \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0b\u0e31\u0e48\u0e19 2569-07-06 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 144\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006440\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e40\u0e19\u0e25 \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006440 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32\u0e40\u0e19\u0e25 \u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006466\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006466 \u0e1a\u0e08.\u0e40\u0e04\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 172\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001519\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e40\u0e25\u0e34\u0e1f \u0e22\u0e39\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001519 \u0e2b\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e40\u0e25\u0e34\u0e1f \u0e22\u0e39 2569-07-06 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01 \u0e44\u0e01\u0e48\u0e2a\u0e14 \u0e44\u0e01\u0e48\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 152\/32  \u0e16\u0e19\u0e19\u0e40\u0e0a\u0e34\u0e14\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001527\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001527 \u0e2b\u0e08.\u0e40\u0e2d\u0e2d\u0e32\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-06 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 250\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19\u0e22\u0e32\u0e07 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003467\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e22\u0e2a\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003467 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e22\u0e2a\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e27\u0e48\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e41\u0e27\u0e48\u0e19\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003475\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e21\u0e35 \u0e40\u0e04\u0e23\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003475 \u0e1a\u0e08.\u0e41\u0e2a\u0e07\u0e21\u0e35 \u0e40\u0e04\u0e23\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e40\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 2\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003483\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003483 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e23\u0e4c\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 43223 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5efa\u8a2d 123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0445569001634\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e34\u0e15\u0e49\u0e32 \u0e2a\u0e27\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001634 \u0e1a\u0e08.\u0e41\u0e2d\u0e19\u0e19\u0e34\u0e15\u0e49\u0e32 \u0e2a\u0e27\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e0a\u0e32\u0e22 \u0e2b\u0e0d\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0503569004371\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e2d \u0e42\u0e2d \u0e14\u0e35 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14115\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14115\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004371 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e2d \u0e42\u0e2d \u0e14\u0e35 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-06 1000000 14115 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e0a\u0e38\u0e14\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u88fd\u9020 222\/216  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004401\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e35\u0e21 \u0e14\u0e35\u0e40\u0e17\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e41\u0e25\u0e47\u0e1a\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004401 \u0e2b\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e35\u0e21 \u0e14\u0e35\u0e40\u0e17\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e41\u0e25\u0e47\u0e1a 2569-07-06 1000000 45203 \u0e25\u0e49\u0e32\u0e07 \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/2  \u0e16\u0e19\u0e19\u0e2d\u0e31\u0e29\u0e0e\u0e32\u0e18\u0e23 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004410\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e04 \u0e01\u0e32\u0e23\u0e32\u0e08\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004410 \u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e04 \u0e01\u0e32\u0e23\u0e32\u0e08 2569-07-06 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e49\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e25\u0e49\u0e32\u0e07\u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e02\u0e31\u0e14\u0e2a\u0e35 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004428\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c.200\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004428 \u0e2b\u0e08.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c.200 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004436\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e33\u0e44\u0e01\u0e48\u0e15\u0e34\u0e14\u0e41\u0e01\u0e23\u0e21\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004436 \u0e2b\u0e08.\u0e15\u0e33\u0e44\u0e01\u0e48\u0e15\u0e34\u0e14\u0e41\u0e01\u0e23\u0e21 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015235\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08.\u0e1a\u0e35. \u0e25\u0e32\u0e19\u0e19\u0e32 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015235 \u0e1a\u0e08.\u0e40\u0e08.\u0e1a\u0e35. \u0e25\u0e32\u0e19\u0e19\u0e32 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001366\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001366 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e07\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 122\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001348\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e0a\u0e38\u0e21\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23959\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23959\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001348 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e0a\u0e38\u0e21\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2569-07-06 1000000 23959 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e48\u0e2d\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e17\u0e48\u0e2d\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e17\u0e48\u0e2d\u0e1b\u0e39\u0e19 \u0e1a\u0e25\u0e4a\u0e2d\u0e04\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001356\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e25\u0e39\u0e1f\u0e34\u0e25\u0e40\u0e21\u0e19\u0e17\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001356 \u0e2b\u0e08.\u0e1f\u0e25\u0e39\u0e1f\u0e34\u0e25\u0e40\u0e21\u0e19\u0e17\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c 2569-07-06 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 809  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 6\/8 \u0e27\u0e31\u0e07\u0e2b\u0e21\u0e49\u0e2d\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e0b\u0e32\u0e27 \u0e16\u0e19\u0e19\u0e25\u0e33\u0e1b\u0e32\u0e07-\u0e41\u0e08\u0e49\u0e2b\u0e48\u0e21 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0543569000261\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e41\u0e2d\u0e17 \u0e42\u0e2e\u0e21\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0543569000261 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e35 \u0e41\u0e2d\u0e17 \u0e42\u0e2e\u0e21 2569-07-06 1000000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u88fd\u9020 8\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0573569002034\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e32\u0e22\u0e25\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002034 \u0e2b\u0e08.\u0e2a\u0e32\u0e22\u0e25\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 2569-07-06 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0b\u0e39\u0e40\u0e25\u0e35\u0e22\u0e19 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22  \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004322\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e28\u0e01\u0e2a\u0e31\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004322 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e28\u0e01\u0e2a\u0e31\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 62\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004331\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e35\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e15\u0e31\u0e07\u0e15\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004331 \u0e1a\u0e08.\u0e15\u0e35\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e15\u0e31\u0e07\u0e15\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 826  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0603569001487\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e21\u0e08\u0e34\u0e17\u0e35\u0e17\u0e35\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47744\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47744\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001487 \u0e2b\u0e08.\u0e42\u0e21\u0e08\u0e34\u0e17\u0e35\u0e17\u0e35 2569-07-06 1000000 47744 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0653569001045\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1a\u0e19\u0e0b\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001045 \u0e2b\u0e08.\u0e40\u0e1a\u0e19\u0e0b\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-06 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 612  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002132\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e20\u0e34\u0e23\u0e21\u0e22\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10772\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10772\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002132 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e20\u0e34\u0e23\u0e21\u0e22\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 10772 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e2d\u0e2a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01 \u88fd\u9020 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0665569000679\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e47\u0e01\u0e01\u0e35\u0e49 \u0e41\u0e1e\u0e47\u0e04\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000679 \u0e1a\u0e08.\u0e41\u0e1a\u0e47\u0e01\u0e01\u0e35\u0e49 \u0e41\u0e1e\u0e47\u0e04\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e0a\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 198\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0665569000687\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e2d\u0e23\u0e23\u0e16 \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000687 \u0e1a\u0e08.\u0e27\u0e35\u0e2d\u0e23\u0e23\u0e16 \u0e40\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 112\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0703569000471\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e04\u0e15\u0e23\u0e08\u0e30\u0e23\u0e27\u0e22\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0703569000471 \u0e2b\u0e08.\u0e42\u0e04\u0e15\u0e23\u0e08\u0e30\u0e23\u0e27\u0e22 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002034\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e22\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e44\u0e2d\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002034 \u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e22\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e44\u0e2d\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569000986\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e21\u0e39\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e2589\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569000986 \u0e2b\u0e08.\u0e2b\u0e21\u0e39\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e2589 2569-07-06 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006790\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e42\u0e1e\u0e25\u0e35\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006790 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e42\u0e1e\u0e25\u0e35\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 242\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006803\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e02\u0e19\u0e2a\u0e48\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006803 \u0e1a\u0e08.\u0e2d\u0e34\u0e48\u0e21\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e02\u0e19\u0e2a\u0e48\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 77\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006811\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35.\u0e1e\u0e35.\u0e40\u0e04. \u0e42\u0e1f\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006811 \u0e1a\u0e08.\u0e17\u0e35.\u0e1e\u0e35.\u0e40\u0e04. \u0e42\u0e1f\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e2a\u0e20\u0e32\u0e1e \u0e23\u0e16\u0e42\u0e1f\u0e25\u0e4c\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c \u88fd\u9020 333\/131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0743569000901\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08 \u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000901 \u0e2b\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08 \u0e1f\u0e39\u0e49\u0e14 2569-07-06 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 253\/252  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0743569000919\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e09\u0e25\u0e34\u0e21 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000919 \u0e2b\u0e08.\u0e40\u0e09\u0e25\u0e34\u0e21 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 2569-07-06 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 253\/252  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007079\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0b\u0e35\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007079 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e0b\u0e35\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b  \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e25\u0e32 \u0e01\u0e38\u0e49\u0e07 \u0e1b\u0e39 \u0e2b\u0e2d\u0e22 \u0e2b\u0e21\u0e36\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e2d\u0e22\u0e39\u0e48\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007087\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e25\u0e34\u0e07\u0e01\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007087 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e25\u0e34\u0e07\u0e01\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007095\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e29\u0e13\u0e32 954 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28229\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28229\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007095 \u0e1a\u0e08.\u0e2d\u0e31\u0e29\u0e13\u0e32 954 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 28229 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0b\u0e36\u0e48\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 117\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0763569000293\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0763569000293 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 2569-07-06 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1060\/50  \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 (\u0e44\u0e17\u0e23\u0e22\u0e49\u0e2d\u0e22) \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0803569000896\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000896 \u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 2569-07-06 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e22\u0e32 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 150\/3  \u0e16\u0e19\u0e19\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0825569001088\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e23\u0e32\u0e23\u0e34\u0e19 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001088 \u0e1a\u0e08.\u0e27\u0e23\u0e32\u0e23\u0e34\u0e19 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0833569000535\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e31\u0e01\u0e04\u0e34\u0e49\u0e27\u0e2a\u0e27\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e34\u0e1b\u0e2a\u0e4c\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85494\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85494\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0833569000535 \u0e2b\u0e08.\u0e2a\u0e31\u0e01\u0e04\u0e34\u0e49\u0e27\u0e2a\u0e27\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e34\u0e1b\u0e2a\u0e4c 2569-07-06 1000000 85494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e01\u0e04\u0e34\u0e49\u0e27\u0e42\u0e2b\u0e07\u0e27\u0e40\u0e2e\u0e49\u0e07 \u0e2a\u0e31\u0e01\u0e04\u0e34\u0e49\u0e27\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e01\u0e49\u0e44\u0e02\u0e04\u0e34\u0e49\u0e27\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e01\u0e04\u0e34\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32  \u0e17\u0e33\u0e1c\u0e21 \u0e17\u0e33\u0e40\u0e25\u0e47\u0e1a \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u6559\u80b2 20\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010061\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010061 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e16\u0e19\u0e19 \u0e41\u0e25\u0e30 \u0e01\u0e33\u0e41\u0e1e\u0e07\u0e01\u0e31\u0e19\u0e14\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5efa\u8a2d 24\/354  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010079\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e2a\u0e2b\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010079 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e2a\u0e2b\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005333\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005333 \u0e1a\u0e08.\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e07\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e44\u0e17\u0e22-\u0e08\u0e31\u0e07\u0e42\u0e2b\u0e25\u0e19 8 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005350\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e37\u0e2d\u0e44\u0e01\u0e25 \u0e44\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005350 \u0e1a\u0e08.\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e07\u0e25\u0e37\u0e2d\u0e44\u0e01\u0e25 \u0e44\u0e17\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 94  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e23\u0e35\u0e2a\u0e22\u0e32\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569000951\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e2d\u0e0a\u0e2a\u0e1b\u0e34\u0e19 89 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569000951 \u0e1a\u0e08.\u0e27\u0e2d\u0e0a\u0e2a\u0e1b\u0e34\u0e19 89 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u88fd\u9020 165\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0935569000757\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000757 \u0e1a\u0e08.\u0e0b\u0e35 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0955569000510\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e17 \u0e40\u0e1a\u0e49\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000510 \u0e1a\u0e08.\u0e41\u0e2e\u0e17 \u0e40\u0e1a\u0e49\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e27\u0e01\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 64\/1  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e41\u0e1b\u0e4a\u0e30\u0e2e\u0e39\u0e25\u0e39 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569006921\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006921 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 2569-07-05 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 74 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126723\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e23\u0e27\u0e22\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126723 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e23\u0e27\u0e22\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\/\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 401-403  \u0e16\u0e19\u0e19\u0e08\u0e31\u0e01\u0e23\u0e27\u0e23\u0e23\u0e14\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126758\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e32 \u0e2b\u0e25\u0e07 \u0e08\u0e35\u0e4b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126758 \u0e1a\u0e08.\u0e40\u0e08\u0e32 \u0e2b\u0e25\u0e07 \u0e08\u0e35\u0e4b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 212\/25  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 28 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126766\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126766 \u0e1a\u0e08.\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e1a\u0e39\u0e48 \u0e40\u0e0b\u0e23\u0e31\u0e48\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2b\u0e19\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 48 \u0e41\u0e22\u0e01 17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126782\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126782 \u0e1a\u0e08.\u0e14\u0e35\u0e14\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 60\/26  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e23\u0e23\u0e04 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126791\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e1e\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126791 \u0e1a\u0e08.\u0e2d\u0e31\u0e1e\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/132  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022146\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e2d\u0e35\u0e27\u0e35\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022146 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25\u0e2d\u0e35\u0e27\u0e35\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/70  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e32\u0e21\u0e41\u0e14\u0e07 \u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569020674\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020674 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 1000000 82199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 23\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0203569002801\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e01\u0e25\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002801 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e01\u0e25\u0e21 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 2569-07-05 1000000 96104 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 (skincare) \u0e40\u0e21\u0e04\u0e2d\u0e31\u0e1e \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e08\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 306\/124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002819\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35 \u0e40\u0e2e\u0e0a  \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46634\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46634\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002819 \u0e2b\u0e08.\u0e1e\u0e35 \u0e40\u0e2e\u0e0a  \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c 2569-07-05 1000000 46634 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001189\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e49\u0e32\u0e22\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58114\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58114\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001189 \u0e2b\u0e08.\u0e1b\u0e49\u0e32\u0e22\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22 2569-07-05 1000000 58114 \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e42\u0e1a\u0e23\u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e43\u0e1a\u0e1b\u0e25\u0e34\u0e27\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46  \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e17\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u60c5\u5831\u901a\u4fe1\u30fbit 468\/83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0273569000468\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35\u0e0b\u0e35  \u0e40\u0e1e\u0e47\u0e17\u0e2a\u0e42\u0e15\u0e23\u0e4c\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0273569000468 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35\u0e0b\u0e35  \u0e40\u0e1e\u0e47\u0e17\u0e2a\u0e42\u0e15\u0e23\u0e4c 2569-07-05 1000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0103569006882\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e0a\u0e31\u0e22\u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006882 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e0a\u0e31\u0e22\u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c 2569-07-04 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e49\u0e01 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e44\u0e27\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e48\u0e07\u0e42\u0e15\u0e4a\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e0a\u0e31\u0e49\u0e19\u0e27\u0e32\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e40\u0e04\u0e32\u0e19\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e39\u0e18 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e14\u0e48\u0e27\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\/\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e40\u0e04\u0e32\u0e19\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e39\u0e18\u0e43\u0e19\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e16\u0e44\u0e1f \u0e40\u0e23\u0e37\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e17\u0e35\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 1908\/1  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006891\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e04\u0e23\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006891 \u0e2b\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e04\u0e23\u0e47\u0e2d\u0e1b\u0e2a\u0e4c \u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01 2569-07-04 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 509\/107  \u0e0b\u0e2d\u0e22 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006904\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2d\u0e30\u0e42\u0e01\u0e23\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006904 \u0e2b\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2d\u0e30\u0e42\u0e01\u0e23 2569-07-04 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 509\/107  \u0e0b\u0e2d\u0e22 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006912\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 99\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006912 \u0e2b\u0e08.\u0e40\u0e01\u0e29\u0e15\u0e23\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 99 2569-07-04 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 509\/107  \u0e0b\u0e2d\u0e22 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126464\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e27\u0e22\u0e4c \u0e40\u0e2d\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126464 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e27\u0e22\u0e4c \u0e40\u0e2d\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 19  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2  \u0e0b\u0e2d\u0e22 69 \u0e41\u0e22\u0e01 3-15-1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126481\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e01\u0e49\u0e32 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126481 \u0e1a\u0e08.\u0e0b\u0e32\u0e01\u0e49\u0e32 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e44\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e07\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 114\/142  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e40\u0e01\u0e49\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 2 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126499\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e47\u0e1a\u0e2d\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126499 \u0e1a\u0e08.\u0e40\u0e01\u0e47\u0e1a\u0e2d\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 86201 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01\u0e1c\u0e21 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e1c\u0e21\u0e23\u0e48\u0e27\u0e07 \u0e1c\u0e21\u0e1a\u0e32\u0e07 \u0e28\u0e35\u0e23\u0e29\u0e30\u0e25\u0e49\u0e32\u0e19 \u0e42\u0e23\u0e04\u0e2b\u0e19\u0e31\u0e07\u0e28\u0e35\u0e23\u0e29\u0e30 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e28\u0e35\u0e23\u0e29\u0e30 \u533b\u7642\u30fb\u798f\u7949 166  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 20 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126502\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e04\u0e48\u0e30 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126502 \u0e1a\u0e08.\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e04\u0e48\u0e30 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 63111 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (software as a service: saas) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32 (platform as a service: paas) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 (subscription service) \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c (software licensing) \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c (cloud service) \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 594\/10  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e32\u0e17\u0e34\u0e42\u0e2d \u0e23\u0e31\u0e0a\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1932 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126511\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e42\u0e1a\u0e42\u0e08\u0e42\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126511 \u0e1a\u0e08.\u0e42\u0e23\u0e42\u0e1a\u0e42\u0e08\u0e42\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 414  \u0e0b\u0e2d\u0e22 \u0e23\u0e27\u0e21\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e17\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126529\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e34\u0e27\u0e31\u0e15\u0e34\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126529 \u0e1a\u0e08.\u0e19\u0e34\u0e15\u0e34\u0e27\u0e31\u0e15\u0e34\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e20\u0e32\u0e29\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 425\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23enco terminal  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 406 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126545\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e2c\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126545 \u0e1a\u0e08.\u0e42\u0e2d\u0e2c\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 77\/22  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e25\u0e25\u0e14\u0e32 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e1954\/1 \u0e41\u0e22\u0e014-45 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126553\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126553 \u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 62022 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 56\/24  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 32 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126570\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126570 \u0e1a\u0e08.\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 54\/63  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e23\u0e23\u0e29\u0e32\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d 3 \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126588\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19\u0e23\u0e38\u0e48\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23109\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23109\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126588 \u0e1a\u0e08.\u0e40\u0e17\u0e35\u0e22\u0e19\u0e23\u0e38\u0e48\u0e22 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 23109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e01\u0e49\u0e27 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19\u0e40\u0e1c\u0e32 \u88fd\u9020 52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126596\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126596 \u0e1a\u0e08.\u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25 \u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 56101 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 77  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126618\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e17\u0e23\u0e34\u0e04\u0e2d\u0e2a\u0e21\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126618 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e17\u0e23\u0e34\u0e04\u0e2d\u0e2a\u0e21\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e  \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1076\/221  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126669\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e40\u0e23\u0e47\u0e17 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126669 \u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e40\u0e23\u0e47\u0e17 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/14  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 111 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126677\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e23\u0e34\u0e07 \u0e40\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126677 \u0e1a\u0e08.\u0e2a\u0e1b\u0e23\u0e34\u0e07 \u0e40\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 11041 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 (oem) \u88fd\u9020 857\/13  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126685\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a. \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126685 \u0e1a\u0e08.\u0e1e\u0e35.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a. \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e32\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 4\/32  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01(\u0e17\u0e48\u0e32\u0e1e\u0e23\u0e30-\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126693\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e04\u0e40\u0e14\u0e47\u0e01\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126693 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e04\u0e40\u0e14\u0e47\u0e01\u0e0b\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c (software) \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c (application) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 359\/152  \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 005\/1 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 005\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002216\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e39 \u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e34\u0e0a\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002216 \u0e2b\u0e08.\u0e17\u0e39 \u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e34\u0e0a 2569-07-04 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e15\u0e40\u0e15\u0e25\u0e47\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/183  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e18\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022081\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022081 \u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 720  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e14\u0e48\u0e32\u0e19 1\/5 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022090\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21\u0e2a\u0e4c \u0e40\u0e04\u0e25\u0e35\u0e22\u0e41\u0e23\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022090 \u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e04\u0e31\u0e2a\u0e15\u0e2d\u0e21\u0e2a\u0e4c \u0e40\u0e04\u0e25\u0e35\u0e22\u0e41\u0e23\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 720  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e14\u0e48\u0e32\u0e19 1\/5 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022103\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022103 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 21\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022111\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022111 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e43\u0e08 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 230\/83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022120\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e20\u0e34\u0e27\u0e23\u0e01\u0e23 \u0e40\u0e1e\u0e25\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25921\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25921\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022120 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e20\u0e34\u0e27\u0e23\u0e01\u0e23 \u0e40\u0e1e\u0e25\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 25921 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e0a\u0e38\u0e1a\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 789  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024971\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024971 \u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e35 \u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 9\/270  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024998\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e01\u0e48\u0e1a\u0e34\u0e19\u0e17\u0e30\u0e25\u0e38\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024998 \u0e1a\u0e08.\u0e44\u0e01\u0e48\u0e1a\u0e34\u0e19\u0e17\u0e30\u0e25\u0e38\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020658\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e2d\u0e21\u0e41\u0e01\u0e07 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020658 \u0e1a\u0e08.\u0e2b\u0e2d\u0e21\u0e41\u0e01\u0e07 \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21 \u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 22\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0193569000728\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e1b\u0e32\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000728 \u0e2b\u0e08.\u0e14\u0e33\u0e23\u0e34\u0e2b\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e1b\u0e32 2569-07-04 1000000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u5efa\u8a2d 16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035336\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e15\u0e34\u0e40\u0e27\u0e17 \u0e21\u0e32\u0e22 \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035336 \u0e1a\u0e08.\u0e41\u0e2d\u0e04\u0e15\u0e34\u0e40\u0e27\u0e17 \u0e21\u0e32\u0e22 \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e0a\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 30\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035361\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35 \u0e01\u0e25\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43302\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43302\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035361 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35 \u0e01\u0e25\u0e32\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 43302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e01\u0e23\u0e30\u0e08\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e21\u0e38\u0e49\u0e07\u0e25\u0e27\u0e14 \u0e1d\u0e49\u0e32\u0e40\u0e1e\u0e14\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 6\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035387\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e22\u0e32\u0e22\u0e42\u0e04\u0e15\u0e23\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035387 \u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e22\u0e32\u0e22\u0e42\u0e04\u0e15\u0e23\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 60\/180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008959\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e14\u0e39\u0e40\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008959 \u0e1a\u0e08.\u0e42\u0e21\u0e14\u0e39\u0e40\u0e23\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 124\/102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e21\u0e34\u0e15\u0e23  17\/1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0235569000397\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e38\u0e4a\u0e01\u0e14\u0e34\u0e4a\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0235569000397 \u0e1a\u0e08.\u0e14\u0e38\u0e4a\u0e01\u0e14\u0e34\u0e4a\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0305569006939\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39.\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e1931 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006939 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39.\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e1931 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e1e\u0e32\u0e19\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 138  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006947\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e0b\u0e31\u0e01\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006947 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e0b\u0e31\u0e01\u0e40\u0e02\u0e32\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0325569001147\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e43\u0e08\u0e14\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001147 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e43\u0e08\u0e14\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e01\u0e14\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u4e0d\u52d5\u7523 61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0405569006423\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006423 \u0e1a\u0e08.\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u4e0d\u52d5\u7523 784  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003459\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e25\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003459 \u0e1a\u0e08.\u0e40\u0e0b\u0e25\u0e2d\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 140\/115  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e16\u0e44\u0e1f \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0445569001626\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e1e\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001626 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e41\u0e1e\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e19\u0e2d\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e25\u0e33\u0e25\u0e2d\u0e07 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0505569015103\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e01\u0e32\u0e40\u0e1b\u0e49 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015103 \u0e1a\u0e08.\u0e2d\u0e32\u0e01\u0e32\u0e40\u0e1b\u0e49 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/71  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015111\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015111 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e25\u0e35\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e2e\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 5\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015120\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e07\u0e28\u0e4c\u0e18\u0e19\u0e42\u0e0a\u0e15\u0e34 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015120 \u0e1a\u0e08.\u0e27\u0e07\u0e28\u0e4c\u0e18\u0e19\u0e42\u0e0a\u0e15\u0e34 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e23\u0e2d\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e1e\u0e37\u0e0a  \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 333\/172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015146\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e22\u0e40\u0e1f\u0e07 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24102\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24102\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015146 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e22\u0e40\u0e1f\u0e07 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 24102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e23\u0e35\u0e14\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e48\u0e2d\u0e2b\u0e25\u0e2d\u0e21\u0e42\u0e25\u0e2b\u0e30 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 197\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015154\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e22\u0e27\u0e19\u0e40\u0e0b\u0e34\u0e49\u0e07\u0e2b\u0e25\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"17012\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"17012\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015154 \u0e1a\u0e08.\u0e2b\u0e22\u0e27\u0e19\u0e40\u0e0b\u0e34\u0e49\u0e07\u0e2b\u0e25\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 17012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e42\u0e23\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e23\u0e31\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u88fd\u9020 27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015162\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e09\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25113\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25113\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015162 \u0e1a\u0e08.\u0e44\u0e09\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 25113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e2a\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e44\u0e21\u0e49 \u0e42\u0e23\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u88fd\u9020 245\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015171\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e04\u0e42\u0e04\u0e48\u0e04\u0e25\u0e31\u0e1a\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015171 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e04\u0e42\u0e04\u0e48\u0e04\u0e25\u0e31\u0e1a\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 29\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 4 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e47\u0e14\u0e22\u0e2d\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0523569001330\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e15\u0e35\u0e22\u0e07\u0e01\u0e38\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001330 \u0e2b\u0e08.\u0e40\u0e15\u0e35\u0e22\u0e07\u0e01\u0e38\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-04 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 158\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 7 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004314\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e07\u0e40\u0e2b\u0e21\u0e22 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004314 \u0e1a\u0e08.\u0e2b\u0e25\u0e34\u0e07\u0e40\u0e2b\u0e21\u0e22 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0665569000661\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e38\u0e2a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000661 \u0e1a\u0e08.\u0e19\u0e38\u0e2a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0715569002468\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002468 \u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 35\/10  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e34\u0e48\u0e19\u0e16\u0e34\u0e48\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000595\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e48\u0e19 \u0e27\u0e35\u0e23\u0e30\u0e01\u0e31\u0e13\u0e10\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e0a\u0e31\u0e22\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000595 \u0e2b\u0e08.\u0e1b\u0e31\u0e48\u0e19\u0e08\u0e31\u0e48\u0e19 \u0e27\u0e35\u0e23\u0e30\u0e01\u0e31\u0e13\u0e10\u0e4c \u0e21\u0e07\u0e04\u0e25\u0e0a\u0e31\u0e22 2569-07-04 1000000 43901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e2d\u0e01\u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19 \u0e23\u0e16\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e48\u0e19\u0e15\u0e35\u0e19\u0e15\u0e30\u0e02\u0e32\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e2e\u0e14\u0e23\u0e2d\u0e25\u0e34\u0e04 \u5efa\u8a2d 69\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006765\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e2d\u0e19 \u0e40\u0e14\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006765 \u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e2d\u0e19 \u0e40\u0e14\u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 47912 \u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0835569012497\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e27\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012497 \u0e1a\u0e08.\u0e23\u0e34\u0e27\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 8\/27  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e1a\u0e22\u0e4c \u0e40\u0e1e\u0e23\u0e2a\u0e15\u0e49\u0e32 \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569125701\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e14\u0e23\u0e49\u0e32 \u0e2d\u0e34\u0e19\u0e42\u0e1f  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01612\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01612\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125701 \u0e1a\u0e08.\u0e44\u0e2e\u0e14\u0e23\u0e49\u0e32 \u0e2d\u0e34\u0e19\u0e42\u0e1f  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 01612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u8fb2\u6797\u6c34\u7523 86  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 7\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125719\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e48\u0e32\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125719 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e48\u0e32\u0e40\u0e2d\u0e2a \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 137\/135  \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e41\u0e22\u0e01 21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125735\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125735 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e4c\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/748  \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e20\u0e34\u0e40\u0e29\u0e01 005\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125743\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e27\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125743 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e27\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/748  \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 005\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125760\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125760 \u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83\/154  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e2219 \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e255 \u0e41\u0e22\u0e0114 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125778\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e25\u0e31\u0e49\u0e01\u0e2d\u0e34\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125778 \u0e1a\u0e08.\u0e1b\u0e25\u0e31\u0e49\u0e01\u0e2d\u0e34\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 57  \u0e0b\u0e2d\u0e22 38(\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e2a\u0e38\u0e02) \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125794\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125794 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 98  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27117(\u0e23\u0e48\u0e27\u0e21\u0e08\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125824\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125824 \u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e22\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 49  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125859\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32\u0e04\u0e35\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125859 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32\u0e04\u0e35\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 428\/201  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2e\u0e32\u0e1a\u0e34\u0e40\u0e17\u0e35\u0e22 \u0e42\u0e21\u0e17\u0e35\u0e1f \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125875\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e42\u0e01\u0e30 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46495\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46495\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125875 \u0e1a\u0e08.\u0e25\u0e34\u0e19\u0e42\u0e01\u0e30 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46495 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125883\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e1a\u0e35 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125883 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e1a\u0e35 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e01\u0e40\u0e40\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 163  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e2169\u0e41\u0e22\u0e015 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125891\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a \u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125891 \u0e1a\u0e08.\u0e41\u0e25\u0e47\u0e1a \u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e23\u0e30\u0e1a\u0e1a internet of things (iot) \u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data analytics) \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 10\/5  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 30 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125913\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125913 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e1a\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e19\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32-\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 11  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b\u0e2d\u0e22 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125964\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e27\u0e23\u0e32 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24320\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24320\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125964 \u0e1a\u0e08.\u0e2d\u0e31\u0e04\u0e23\u0e27\u0e23\u0e32 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 24320 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e07\u0e34\u0e19 \u0e19\u0e32\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e2d\u0e21 \u88fd\u9020 29-29\/1  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e13\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125972\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e21\u0e34\u0e14\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10752\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10752\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125972 \u0e1a\u0e08.\u0e40\u0e2d\u0e21\u0e21\u0e34\u0e14\u0e32 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 10752 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e01\u0e32\u0e41\u0e1f \u0e2a\u0e41\u0e19\u0e47\u0e04 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 200\/167  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 42 \u0e41\u0e22\u0e01 27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125981\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125981 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e1b\u0e01\u0e15\u0e34 \u6559\u80b2 146\/2  \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125999\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e08 \u0e1a\u0e38\u0e0d\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125999 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e08 \u0e1a\u0e38\u0e0d\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e14\u0e39\u0e41\u0e25 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 1\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126006\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126006 \u0e1a\u0e08.\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1c\u0e25\u0e34\u0e15\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e35\u0e2c\u0e32\u0e21\u0e27\u0e22\u0e44\u0e17\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 77\/23  \u0e0b\u0e2d\u0e22 \u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 6 \u0e0b\u0e2d\u0e22 7 \u0e41\u0e22\u0e01 3-8 (\u0e22\u0e34\u0e49\u0e21\u0e2a\u0e22\u0e32\u0e21) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126031\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126031 \u0e1a\u0e08.\u0e15\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e15\u0e48\u0e32\u0e07 \u0e46 \u91d1\u878d\u30fb\u4fdd\u967a 13\/105  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126049\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e14\u0e32 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126049 \u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e14\u0e32 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e07\u0e42\u0e09\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e22\u0e32\u0e2a\u0e35\u0e1f\u0e31\u0e19 \u0e2a\u0e1a\u0e39\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e1b\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/3  \u0e0b\u0e2d\u0e22 20 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32 11 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126065\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e40\u0e25\u0e0b\u0e25\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126065 \u0e1a\u0e08.\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f \u0e40\u0e25\u0e0b\u0e25\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 192\/71  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 36 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126081\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e1e\u0e2a\u0e01\u0e34\u0e25\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126081 \u0e1a\u0e08.\u0e2d\u0e31\u0e1e\u0e2a\u0e01\u0e34\u0e25\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e19\u0e30\u0e41\u0e19\u0e27 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1938  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126103\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e1f \u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126103 \u0e1a\u0e08.\u0e27\u0e35\u0e1f \u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e23\u0e38\u0e4a\u0e1b\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19-\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e1a\u0e31\u0e2a \u0e23\u0e16\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 9\/135  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 72 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126111\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e32\u0e2a\u0e21\u0e48\u0e32 \u0e41\u0e25\u0e47\u0e1a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126111 \u0e1a\u0e08.\u0e1e\u0e25\u0e32\u0e2a\u0e21\u0e48\u0e32 \u0e41\u0e25\u0e47\u0e1a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 10\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 4 \u0e41\u0e22\u0e01 23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126120\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126120 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e13\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 805  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32 2 \u0e16\u0e19\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126138\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e2a\u0e21\u0e31\u0e22 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126138 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e2a\u0e21\u0e31\u0e22 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48  \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 829  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2787(\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e38\u0e02) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126146\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e42\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126146 \u0e1a\u0e08.\u0e23\u0e27\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e42\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e08\u0e33\u0e19\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19             \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e0d\u52d5\u7523 299  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e21\u0e19\u0e18\u0e32\u0e15\u0e38 9 \u0e41\u0e22\u0e01 17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126162\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e34\u0e19\u0e14\u0e35\u0e21\u0e35\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47822\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47822\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126162 \u0e1a\u0e08.\u0e40\u0e14\u0e34\u0e19\u0e14\u0e35\u0e21\u0e35\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47822 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200\/11  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 190\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126219\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e23\u0e40\u0e0b\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126219 \u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e23\u0e40\u0e0b\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 45201 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 131  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126243\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126243 \u0e1a\u0e08.\u0e23\u0e31\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e0a\u0e48\u0e19  \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 524\/16  \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126251\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126251 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e35\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 149\/4   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 d-004 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126260\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e1e\u0e2d\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126260 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e1e\u0e2d\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 798\/14  \u0e0b\u0e2d\u0e22 \u0e2a\u0e27\u0e19\u0e1e\u0e25\u0e39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126286\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e0b\u0e25\u0e34\u0e40\u0e14\u0e17 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126286 \u0e1a\u0e08.\u0e19\u0e34\u0e27 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e0b\u0e25\u0e34\u0e40\u0e14\u0e17 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e22\u0e37\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e44\u0e1e\u0e42\u0e23\u0e44\u0e25\u0e0b\u0e34\u0e2a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126308\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e07\u0e42\u0e01\u0e49 \u0e42\u0e2e\u0e21 \u0e2d\u0e32\u0e22\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47731\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47731\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126308 \u0e1a\u0e08.\u0e41\u0e21\u0e07\u0e42\u0e01\u0e49 \u0e42\u0e2e\u0e21 \u0e2d\u0e32\u0e22\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47731 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e27\u0e48\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e27\u0e48\u0e19 \u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e41\u0e27\u0e48\u0e19\u0e2a\u0e32\u0e22\u0e15\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/23  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126316\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e2d\u0e42\u0e19\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126316 \u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e2d\u0e42\u0e19\u0e48 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c ,\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e25\u0e33\u0e42\u0e1e\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 719  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s012 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 23 \u0e42\u0e0b\u0e19 c \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126332\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e34\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47999\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47999\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126332 \u0e1a\u0e08.\u0e1e\u0e23\u0e34\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e16 \u0e42\u0e2d\u0e19 \u0e22\u0e49\u0e32\u0e22 \u0e23\u0e16 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a.\u0e41\u0e2d\u0e25.\u0e40\u0e23\u0e0b\u0e34\u0e40\u0e14\u0e49\u0e19\u0e17\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e22\u0e32\u0e2a\u0e39\u0e1a 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126341\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e08\u0e34\u0e40\u0e0b\u0e04 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126341 \u0e1a\u0e08.\u0e40\u0e2d\u0e08\u0e34\u0e40\u0e0b\u0e04 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c (cybersecurity) \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 111 \u0e17\u0e23\u0e39 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e40\u0e27\u0e2a\u0e15\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e22\u0e39\u0e19\u0e34\u0e04\u0e2d\u0e23\u0e4c\u0e19 \u0e0a\u0e31\u0e49\u0e19 5 \u0e22\u0e39\u0e19\u0e34\u0e15 sh578 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126375\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e2d\u0e23\u0e4c\u0e21\u0e41\u0e1a\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126375 \u0e1a\u0e08.\u0e27\u0e2d\u0e23\u0e4c\u0e21\u0e41\u0e1a\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e19\u0e33\u0e49\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/6  \u0e0b\u0e2d\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e075 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126383\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20291\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20291\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126383 \u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e32 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15-\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 20291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e14\u0e41\u0e25\u0e30\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14 \u0e01\u0e23\u0e30\u0e2a\u0e38\u0e19\u0e1b\u0e37\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e27\u0e38\u0e18\u0e1b\u0e37\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 44  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e21\u0e19\u0e18\u0e32\u0e15\u0e38\u0e2f \u0e41\u0e22\u0e01 35-6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126391\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126391 \u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 41  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 48 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126448\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e27\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126448 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e27\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e0d\u52d5\u7523 1322  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 26 \u0e41\u0e22\u0e01 6-1 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 - \u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126456\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e2d\u0e01\u0e0a\u0e2d\u0e1a\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126456 \u0e1a\u0e08.\u0e0a\u0e2d\u0e1a\u0e2d\u0e01\u0e0a\u0e2d\u0e1a\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a 18 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021956\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e1e\u0e1e\u0e32\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021956 \u0e1a\u0e08.\u0e19\u0e34\u0e1e\u0e1e\u0e32\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e1c\u0e07\u0e0b\u0e31\u0e01\u0e1f\u0e2d\u0e01 \u0e41\u0e0a\u0e21\u0e1e\u0e39 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e08\u0e32\u0e19 \u0e02\u0e19\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30 \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 561  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022057\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e23\u0e2d\u0e19\u0e40\u0e21\u0e19\u0e17\u0e31\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"36002\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"36002\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022057 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e27\u0e23\u0e2d\u0e19\u0e40\u0e21\u0e19\u0e17\u0e31\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 36002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 33\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024769\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e38\u0e4b\u0e22\u0e22\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024769 \u0e1a\u0e08.\u0e1b\u0e38\u0e4b\u0e22\u0e22\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\/\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e16\u0e36\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024807\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024807 \u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/57  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e32\u0e17\u0e34\u0e42\u0e2d \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19 \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e1923 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024815\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e04\u0e1f \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85429\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85429\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024815 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e04\u0e1f \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 85429 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e04\u0e2d\u0e23\u0e4c\u0e2a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19 (coach) \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e32\u0e23\u0e25\u0e30\u0e04\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e42\u0e0a\u0e27\u0e4c\u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1a\u0e38\u0e04\u0e25\u0e34\u0e01\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e47\u0e2d\u0e1b\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u6559\u80b2 89\/1465  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e215-\u0e1a\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024823\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e34\u0e19\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024823 \u0e1a\u0e08.\u0e04\u0e27\u0e34\u0e19\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u82b8\u8853\u30fb\u5a2f\u697d 85\/19  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04 44 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024858\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e19\u0e36\u0e01\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024858 \u0e1a\u0e08.\u0e2a\u0e21\u0e19\u0e36\u0e01\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2f\u0e25\u0e2f \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 78,80  \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024866\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024866 \u0e1a\u0e08.\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\/\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 371  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e25\u0e34\u0e15\u0e40\u0e15\u0e34\u0e49\u0e25 \u0e27\u0e2d\u0e25\u0e4c\u0e04  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a3-16,17,18 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024882\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e1e\u0e23\u0e4c\u0e19\u0e34\u0e04\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024882 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e25\u0e1f\u0e4c \u0e41\u0e1e\u0e23\u0e4c\u0e19\u0e34\u0e04\u0e40\u0e04\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 199\/122  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e2a\u0e27\u0e19\u0e1c\u0e31\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024891\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e15\u0e23\u0e40\u0e19\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024891 \u0e1a\u0e08.\u0e44\u0e15\u0e23\u0e40\u0e19\u0e17\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e2d\u0e17\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15            \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c  \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/108  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e13\u0e35\u0e22\u0e32\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e35\u0e0a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024904\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35 \u0e42\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47412\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47412\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024904 \u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35 \u0e42\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47412 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86\/173  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024921\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e18\u0e32\u0e23\u0e32\u0e20\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024921 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e18\u0e32\u0e23\u0e32\u0e20\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25 \u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e02\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e19\u0e49\u0e33 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 107\/147  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e14\u0e32 \u0e44\u0e25\u0e17\u0e4c \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 15 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024955\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e04\u0e39\u0e25\u0e1a\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024955 \u0e1a\u0e08.\u0e44\u0e2d\u0e04\u0e39\u0e25\u0e1a\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e1a\u0e32\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e47\u0e2d\u0e01 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 108\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002224\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e1b\u0e17\u0e38\u0e21\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01496\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01496\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002224 \u0e2b\u0e08.\u0e1a\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c \u0e41\u0e04\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e35\u0e48 \u0e1b\u0e17\u0e38\u0e21 2569-07-03 1000000 01496 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e40\u0e1e\u0e32\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38 \u0e02\u0e22\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 99\/327  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e17\u0e23\u0e31\u0e2a\u0e15\u0e4c\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020577\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e27 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020577 \u0e1a\u0e08.\u0e1e\u0e32\u0e27 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u5efa\u8a2d 69\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020585\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e2a\u0e35\u0e48\u0e02\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020585 \u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e2a\u0e35\u0e48\u0e02\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1c\u0e2a\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2b\u0e31\u0e27\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1e\u0e27\u0e01\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e41\u0e23\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e1c\u0e2a\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e23\u0e23\u0e21\u0e27\u0e34\u0e18\u0e35\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e1e\u0e25\u0e2d\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e06\u0e48\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u88fd\u9020 65\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020623\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e0c\u0e32 \u0e40\u0e17\u0e23\u0e19\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020623 \u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e0c\u0e32 \u0e40\u0e17\u0e23\u0e19\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07  \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e40\u0e27\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e41\u0e02\u0e19\u0e22\u0e32\u0e27 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e04\u0e32\u0e23\u0e4c\u0e14\u0e34\u0e41\u0e01\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2e\u0e39\u0e49\u0e14\u0e14\u0e35\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19  \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 211  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020631\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e1b \u0e2a\u0e39\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020631 \u0e1a\u0e08.\u0e2a\u0e25\u0e35\u0e1b \u0e2a\u0e39\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e19\u0e2d\u0e19 \u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e0d\u0e48 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51\/342  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020640\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19  \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81299\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81299\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020640 \u0e1a\u0e08.\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19  \u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 81299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e25\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14  \u0e23\u0e16\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27  \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 44\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004407\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e01\u0e0b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004407 \u0e1a\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e01\u0e0b\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0155569000541\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0155569000541 \u0e1a\u0e08.\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0165569001491\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 148 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001491 \u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 148 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 117  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e04\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000701\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000701 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-03 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 45\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002447\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e01\u0e32\u0e0a\u0e34 \u0e02\u0e19\u0e21\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002447 \u0e1a\u0e08.\u0e27\u0e32\u0e01\u0e32\u0e0a\u0e34 \u0e02\u0e19\u0e21\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c  \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e15\u0e38\u0e4a\u0e01\u0e15\u0e32 \u0e40\u0e01\u0e21 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e2b\u0e49\u0e32\u0e21\u0e44\u0e27\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002455\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e23\u0e14\u0e27\u0e39\u0e14 \u0e40\u0e27\u0e25\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002455 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e23\u0e14\u0e27\u0e39\u0e14 \u0e40\u0e27\u0e25\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e21\u0e31\u0e17\u0e09\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/67  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002463\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1a\u0e35 \u0e40\u0e17\u0e04\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0b\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002463 \u0e1a\u0e08.\u0e40\u0e04\u0e1a\u0e35 \u0e40\u0e17\u0e04\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0b\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 62011 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49 (\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e23\u0e30\u0e1a\u0e1a) \u60c5\u5831\u901a\u4fe1\u30fbit 343  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002789\",\"name_th\":\"\u0e2b\u0e08.\u0e1b.\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002789 \u0e2b\u0e08.\u0e1b.\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-03 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e0a\u0e32 \u0e0a\u0e32\u0e19\u0e21\u0e44\u0e02\u0e48\u0e21\u0e38\u0e01 \u0e01\u0e32\u0e41\u0e1f \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 84\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035107\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e08\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47731\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47731\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035107 \u0e1a\u0e08.\u0e27\u0e32\u0e08\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47731 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e42\u0e1b\u0e23\u0e40\u0e01\u0e23\u0e2a\u0e0b\u0e35\u0e1f \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e04\u0e40\u0e25\u0e19\u0e2a\u0e4c \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e17\u0e31\u0e28\u0e19\u0e21\u0e32\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e14\u0e27\u0e07\u0e15\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/183  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035115\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e32\u0e22 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 24 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52214\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52214\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035115 \u0e1a\u0e08.\u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e32\u0e22 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 24 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 52214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e23\u0e16 \u904b\u8f38\u30fb\u7269\u6d41 52\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035123\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e2d 888 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035123 \u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e2d 888 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e16\u0e21\u0e17\u0e35\u0e48 \u0e40\u0e01\u0e25\u0e35\u0e48\u0e22\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e25\u0e30\u0e23\u0e31\u0e07\u0e27\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e41\u0e22\u0e01\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e19\u0e27\u0e40\u0e02\u0e15 \u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e17\u0e18\u0e34 \u0e23\u0e31\u0e07\u0e27\u0e31\u0e14\u0e15\u0e32\u0e21\u0e42\u0e09\u0e19\u0e14\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07 \u0e08\u0e31\u0e14\u0e25\u0e47\u0e2d\u0e04 \u0e41\u0e1a\u0e48\u0e07\u0e41\u0e22\u0e01 \u0e04\u0e33\u0e19\u0e27\u0e13\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e07\u0e27\u0e31\u0e14\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 888  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035131\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e15\u0e4a\u0e30\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035131 \u0e1a\u0e08.\u0e42\u0e15\u0e4a\u0e30\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 16220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e17\u0e33 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e42\u0e15\u0e4a\u0e30 \u0e15\u0e39\u0e49 \u0e40\u0e15\u0e35\u0e22\u0e07 \u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e17\u0e33\u0e14\u0e49\u0e27\u0e22\u0e44\u0e21\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u88fd\u9020 185\/63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035166\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e27\u0e39\u0e14\u0e25\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16230\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16230\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035166 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35 \u0e27\u0e39\u0e14\u0e25\u0e47\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 16230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e1e\u0e32\u0e40\u0e25\u0e17\u0e44\u0e21\u0e49 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e21\u0e49 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e1e\u0e47\u0e01\u0e01\u0e34\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u88fd\u9020 106\/99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035182\",\"name_th\":\"\u0e1a\u0e08.\u0e1d\u0e39 \u0e2d\u0e31\u0e19 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035182 \u0e1a\u0e08.\u0e1d\u0e39 \u0e2d\u0e31\u0e19 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58\/9  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e27\u0e34\u0e0a\u0e31\u0e22 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035204\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035204 \u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 114\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035212\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e19\u0e40\u0e1a\u0e25\u0e0b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e21\u0e32\u0e23\u0e35\u0e44\u0e17\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035212 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e19\u0e40\u0e1a\u0e25\u0e0b \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e21\u0e32\u0e23\u0e35\u0e44\u0e17\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 730  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035221\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e07\u0e1f\u0e39\u0e48 \u0e40\u0e2d\u0e1f\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22292\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22292\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035221 \u0e1a\u0e08.\u0e2b\u0e07\u0e1f\u0e39\u0e48 \u0e40\u0e2d\u0e1f\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 22292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e01\u0e25\u0e32\u0e2a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e23\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22 (frp) \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e04\u0e2d\u0e21\u0e42\u0e1e\u0e2a\u0e34\u0e15 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e23\u0e0b\u0e34\u0e19 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 189\/78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035255\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e1724 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035255 \u0e1a\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e1e\u0e47\u0e1724 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e02\u0e19\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e1b\u0e25\u0e2d\u0e01\u0e04\u0e2d \u0e2a\u0e32\u0e22\u0e08\u0e39\u0e07 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19 \u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e23\u0e07 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e41\u0e21\u0e27 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e02\u0e19 \u0e41\u0e0a\u0e21\u0e1e\u0e39 \u0e17\u0e23\u0e32\u0e22\u0e41\u0e21\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07 \u0e02\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 18\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035271\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 88 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66123\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66123\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035271 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 88 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 66123 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u91d1\u878d\u30fb\u4fdd\u967a 312\/78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035280\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e14\u0e4c\u0e41\u0e1a\u0e14 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035280 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e14\u0e4c\u0e41\u0e1a\u0e14 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 79110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e41\u0e01\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 326\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035310\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e0b\u0e38\u0e48\u0e19\u0e44\u0e17\u0e48 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035310 \u0e1a\u0e08.\u0e40\u0e2b\u0e2d\u0e0b\u0e38\u0e48\u0e19\u0e44\u0e17\u0e48 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 49339 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 566  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008908\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e04 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008908 \u0e1a\u0e08.\u0e40\u0e17\u0e04 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 71209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d \u0e16\u0e31\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e14\u0e34\u0e1a \u0e01\u0e4a\u0e32\u0e0b\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e01\u0e4a\u0e32\u0e0b\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21\u0e40\u0e2b\u0e25\u0e27\u0e41\u0e25\u0e30\u0e01\u0e4a\u0e32\u0e0b\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 79\/244  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008916\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008916 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e35\u0e27\u0e35 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e31\u0e19\u0e14\u0e32\u0e1b\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32  (electric vehicle conversion) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008924\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e07\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008924 \u0e1a\u0e08.\u0e1f\u0e32\u0e07\u0e40\u0e0b\u0e34\u0e48\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 678\/20  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e28\u0e34\u0e18\u0e23 26 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 2\/1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008941\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e27\u0e31\u0e19 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46631\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46631\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008941 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e27\u0e31\u0e19 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46631 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34 \u0e2b\u0e34\u0e19\u0e04\u0e25\u0e38\u0e01 \u0e2b\u0e34\u0e19 3\/4 \u0e2b\u0e34\u0e19\u0e40\u0e01\u0e25\u0e47\u0e14 \u0e2b\u0e34\u0e19\u0e1d\u0e38\u0e48\u0e19 \u0e17\u0e23\u0e32\u0e22\u0e2b\u0e22\u0e32\u0e1a \u0e17\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e17\u0e23\u0e32\u0e22\u0e16\u0e21 \u0e14\u0e34\u0e19\u0e25\u0e39\u0e01\u0e23\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/51  \u0e16\u0e19\u0e19\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e2236 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002101\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002101 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 128\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569001920\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27 \u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47742\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47742\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001920 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27 \u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47742 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 242\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0263569000158\",\"name_th\":\"\u0e2b\u0e08.\u0e13\u0e31\u0e10\u0e23\u0e34\u0e28\u0e32\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0263569000158 \u0e2b\u0e08.\u0e13\u0e31\u0e10\u0e23\u0e34\u0e28\u0e32 2569-07-03 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 117\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0265569000761\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000761 \u0e1a\u0e08.\u0e1a\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 35101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0305569006904\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e27\u0e35\u0e1c\u0e25\u0e25\u0e32\u0e20 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006904 \u0e1a\u0e08.\u0e17\u0e27\u0e35\u0e1c\u0e25\u0e25\u0e32\u0e20 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e25\u0e49\u0e32\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 165  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006912\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006912 \u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e43\u0e2b\u0e0d\u0e48\u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001821\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e2a\u0e40\u0e0b\u0e34\u0e25 \u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001821 \u0e1a\u0e08.\u0e04\u0e32\u0e2a\u0e40\u0e0b\u0e34\u0e25 \u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c (event) \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e42\u0e0a\u0e27\u0e4c  \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 6\/42  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e40\u0e1e\u0e47\u0e0a\u0e23 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0335569001112\",\"name_th\":\"\u0e1a\u0e08.\u0e2a. \u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001112 \u0e1a\u0e08.\u0e2a. \u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c  \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 27\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0383569000262\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e27\u0e07\u0e28\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 77\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01122\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01122\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0383569000262 \u0e2b\u0e08.\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e27\u0e07\u0e28\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 77 2569-07-03 1000000 01122 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2b\u0e34\u0e19 \u0e1b\u0e39\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u8fb2\u6797\u6c34\u7523 1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e2b\u0e31\u0e27\u0e0a\u0e49\u0e32\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0395569000434\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e1e\u0e34\u0e0a\u0e0d\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93191\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93191\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000434 \u0e1a\u0e08.\u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e1e\u0e34\u0e0a\u0e0d\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 93191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e25\u0e35\u0e01\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u82b8\u8853\u30fb\u5a2f\u697d 171\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0403569002914\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e19\u0e01\u0e1e\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002914 \u0e2b\u0e08.\u0e01\u0e19\u0e01\u0e1e\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-03 1000000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23 \u0e2a\u0e38\u0e01\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e38\u0e01\u0e23\u0e02\u0e38\u0e19 \u8fb2\u6797\u6c34\u7523 107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006342\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e34\u0e25\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e42\u0e2d\u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006342 \u0e1a\u0e08.\u0e1e\u0e34\u0e21\u0e1e\u0e34\u0e25\u0e32 \u0e40\u0e2d\u0e47\u0e19\u0e42\u0e2d\u0e40\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e40\u0e0b\u0e23\u0e31\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u88fd\u9020 335-335\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006351\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e1a\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006351 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e1a\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e1c\u0e48\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e2d\u0e41\u0e1e\u0e14 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e27\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 193\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006369\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e19 \u0e2a\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006369 \u0e1a\u0e08.\u0e41\u0e21\u0e19 \u0e2a\u0e1a\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e43\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e1a\u0e2d\u0e01\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 166  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006385\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006385 \u0e1a\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e32\u0e27\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e34\u0e40\u0e17\u0e04 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 241  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001497\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 \u0e44\u0e2d\u0e17\u0e35\u0e2d\u0e38\u0e14\u0e23\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001497 \u0e2b\u0e08.\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 \u0e44\u0e2d\u0e17\u0e35\u0e2d\u0e38\u0e14\u0e23 2569-07-03 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e0b\u0e48\u0e2d\u0e21 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e19\u0e4a\u0e15\u0e1a\u0e38\u0e4a\u0e04 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 119\/138  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001501\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e14\u0e35\u0e14\u0e35 2026\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001501 \u0e2b\u0e08.\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e14\u0e35\u0e14\u0e35 2026 2569-07-03 1000000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 359  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003432\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003432 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 21001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e04\u0e23\u0e35\u0e21\u0e17\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 211  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003441\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e31\u0e25 \u0e40\u0e2e\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86903\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86903\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003441 \u0e1a\u0e08.\u0e44\u0e1a\u0e42\u0e2d\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e31\u0e25 \u0e40\u0e2e\u0e25\u0e18\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 86903 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e32\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e25\u0e37\u0e2d\u0e14 \u0e15\u0e23\u0e27\u0e08\u0e1b\u0e31\u0e2a\u0e2a\u0e32\u0e27\u0e30 \u0e2a\u0e32\u0e23\u0e04\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e48\u0e07 \u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27\u0e08\u0e32\u0e01\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e23\u0e27\u0e08\u0e2b\u0e32\u0e21\u0e30\u0e40\u0e23\u0e47\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u533b\u7642\u30fb\u798f\u7949 239\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000709\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e04\u0e49\u0e27\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46631\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46631\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000709 \u0e2b\u0e08.\u0e42\u0e04\u0e49\u0e27\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 2569-07-03 1000000 46631 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2d\u0e34\u0e10 \u0e2b\u0e34\u0e19 \u0e1b\u0e39\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 285\/168  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e04\u0e32\u0e41\u0e19\u0e25 \u0e16\u0e19\u0e19\u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e21\u0e16\u0e27\u0e34\u0e25 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0443569000717\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e31\u0e13\u0e11\u0e34\u0e23\u0e32 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000717 \u0e2b\u0e08.\u0e20\u0e31\u0e13\u0e11\u0e34\u0e23\u0e32 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-03 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e25\u0e32\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001618\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e27\u0e34 \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46495\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46495\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001618 \u0e1a\u0e08.\u0e23\u0e34\u0e27\u0e34 \u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46495 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e19 \u0e0a\u0e32\u0e21 \u0e16\u0e49\u0e27\u0e22 \u0e41\u0e01\u0e49\u0e27\u0e19\u0e49\u0e33 \u0e20\u0e32\u0e0a\u0e19\u0e30\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e42\u0e15\u0e4a\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19\u0e40\u0e1c\u0e32\u0e41\u0e25\u0e30\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0455569001383\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e1a\u0e39\u0e25\u0e22\u0e4c\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001383 \u0e1a\u0e08.\u0e27\u0e34\u0e1a\u0e39\u0e25\u0e22\u0e4c\u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 311  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e0a\u0e31\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e2a\u0e19\u0e34\u0e17 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0455569001391\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e0a\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001391 \u0e1a\u0e08.\u0e2b\u0e31\u0e27\u0e0a\u0e49\u0e32\u0e07\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0503569004321\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e38\u0e23\u0e32\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004321 \u0e2b\u0e08.\u0e19\u0e32\u0e22\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e38\u0e23\u0e32 2569-07-03 1000000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e08\u0e32\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e32 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67\/51  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015006\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015006 \u0e1a\u0e08.\u0e1a\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e23\u0e35\u0e22\u0e07 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 15\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015014\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e41\u0e2d\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015014 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e41\u0e2d\u0e25 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 50150660685   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 338\/27 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e0d\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e01\u0e19\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015031\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e22\u0e39\u0e42\u0e23 \u0e14\u0e35\u0e44\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015031 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e22\u0e39\u0e42\u0e23 \u0e14\u0e35\u0e44\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 197\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015057\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e01\u0e0b\u0e4c-\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015057 \u0e1a\u0e08.\u0e1f\u0e34\u0e01\u0e0b\u0e4c-\u0e2d\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569002026\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e14\u0e0a \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002026 \u0e2b\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e14\u0e0a \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c 2569-07-03 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0635569001403\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e21\u0e42\u0e19\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46621\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46621\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001403 \u0e1a\u0e08.\u0e2d\u0e32\u0e40\u0e21\u0e42\u0e19\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46621 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 579  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0665569000652\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000652 \u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 84  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0675569001411\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e1e\u0e37\u0e0a\u0e1c\u0e25(2020) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001411 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e1e\u0e37\u0e0a\u0e1c\u0e25(2020) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0715569002441\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39\u0e17\u0e35\u0e1e\u0e35\u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10615\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10615\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002441 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39\u0e17\u0e35\u0e1e\u0e35\u0e23\u0e35\u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 10615 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e33\u0e27\u0e38\u0e49\u0e19\u0e40\u0e2a\u0e49\u0e19 \u0e0b\u0e32\u0e2b\u0e23\u0e34\u0e48\u0e21 \u0e41\u0e1b\u0e49\u0e07\u0e16\u0e31\u0e48\u0e27\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e49\u0e07\u0e16\u0e31\u0e48\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e41\u0e1b\u0e49\u0e07\u0e16\u0e31\u0e48\u0e27\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u88fd\u9020 25\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002450\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e30 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002450 \u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e30 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e19\u0e49\u0e15\u0e1a\u0e38\u0e4a\u0e01 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15\u0e42\u0e1f\u0e19 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569000978\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21 \u0e40\u0e1f\u0e23\u0e0a\u0e21\u0e35\u0e17\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569000978 \u0e2b\u0e08.\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e2d\u0e21 \u0e40\u0e1f\u0e23\u0e0a\u0e21\u0e35\u0e17 2569-07-03 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006714\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.\u0e08\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006714 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.\u0e08\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 112\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006722\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e2a\u0e1e\u0e35  \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006722 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e2a\u0e1e\u0e35  \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006749\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e27\u0e31\u0e07\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e32\u0e13\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006749 \u0e1a\u0e08.\u0e2b\u0e27\u0e31\u0e07\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e32\u0e13\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0743569000889\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000889 \u0e2b\u0e08.\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-03 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 6\/4  \u0e16\u0e19\u0e19\u0e18\u0e23\u0e23\u0e21\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0743569000897\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000897 \u0e2b\u0e08.\u0e27\u0e35 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 2569-07-03 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 1300\/184  \u0e16\u0e19\u0e19\u0e19\u0e23\u0e23\u0e32\u0e0a\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569006994\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569006994 \u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 27101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e2d\u0e01\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e15\u0e39\u0e49\u0e44\u0e1f\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 75\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569007010\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007010 \u0e1a\u0e08.\u0e42\u0e2d\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 49\/997  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0765569001411\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001411 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46  \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569002859\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e40\u0e14\u0e25 \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e17 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002859 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e40\u0e14\u0e25 \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e17 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e17\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002521\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002521 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 146\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002530\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e47\u0e15\u0e0b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002530 \u0e1a\u0e08.\u0e40\u0e21\u0e47\u0e15\u0e0b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11  \u0e16\u0e19\u0e19\u0e1b\u0e32\u0e01\u0e19\u0e04\u0e23 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002548\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e35\u0e48\u0e40\u0e04 \u0e22\u0e32\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002548 \u0e1a\u0e08.\u0e2a\u0e35\u0e48\u0e40\u0e04 \u0e22\u0e32\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0835569012454\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e2d\u0e35\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 69 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012454 \u0e1a\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e2d\u0e35\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 69 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u5efa\u8a2d 8\/129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012471\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e41\u0e25\u0e47\u0e1a \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012471 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e41\u0e25\u0e47\u0e1a \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 79\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0865569001177\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e39\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001177 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e39\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 866  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001468\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e38\u0e11\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001468 \u0e2b\u0e08.\u0e08\u0e38\u0e11\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-03 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e22\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e22\u0e32\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e22\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35  \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e192 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005252\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e40\u0e19\u0e15\u0e34\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005252 \u0e1a\u0e08.\u0e2a\u0e01\u0e32\u0e22\u0e40\u0e19\u0e15\u0e34\u0e01\u0e0b\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e15\u0e14\u0e31\u0e49\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e15\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 245  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e22\u0e34\u0e19\u0e14\u0e35 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005279\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e40\u0e0a\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005279 \u0e1a\u0e08.\u0e23\u0e32\u0e40\u0e0a\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 346\/2  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0915569000315\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e32\u0e04\u0e34\u0e19456 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0915569000315 \u0e1a\u0e08.\u0e20\u0e32\u0e04\u0e34\u0e19456 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e42\u0e14\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 215  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569006751\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e25\u0e39\u0e2a\u0e23\u0e2d\u0e19\u0e1e\u0e32\u0e27\u0e25\u0e4c\u0e17\u0e23\u0e35\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006751 \u0e2b\u0e08.\u0e1a\u0e25\u0e39\u0e2a\u0e23\u0e2d\u0e19\u0e1e\u0e32\u0e27\u0e25\u0e4c\u0e17\u0e23\u0e35\u0e1f\u0e32\u0e21 2569-07-02 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006769\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e08 \u0e44\u0e1f\u0e19\u0e4c\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006769 \u0e2b\u0e08.\u0e40\u0e2d\u0e08 \u0e44\u0e1f\u0e19\u0e4c\u0e1f\u0e32\u0e21 2569-07-02 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006777\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e42\u0e1b\u0e23\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006777 \u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e42\u0e1b\u0e23\u0e1f\u0e32\u0e21 2569-07-02 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006785\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04.\u0e17\u0e35. \u0e27\u0e31\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e34\u0e2a\u0e2a\u0e34\u0e40\u0e19\u0e2a\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006785 \u0e2b\u0e08.\u0e40\u0e04.\u0e17\u0e35. \u0e27\u0e31\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1a\u0e34\u0e2a\u0e2a\u0e34\u0e40\u0e19\u0e2a 2569-07-02 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30\/65  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 5 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006807\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e17\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e01\u0e40\u0e1a\u0e34\u0e25\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006807 \u0e2b\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e17\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e01\u0e40\u0e1a\u0e34\u0e25 2569-07-02 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e23\u0e31\u0e1a\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 10  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e1421 \u0e40\u0e40\u0e22\u0e0113 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006815\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e21\u0e32 \u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e08\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006815 \u0e2b\u0e08.\u0e21\u0e32\u0e21\u0e32 \u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e08 2569-07-02 1000000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e2a\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 4\/3  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 33 (\u0e41\u0e14\u0e07\u0e2d\u0e38\u0e14\u0e21) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006823\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d \u0e1e\u0e24\u0e01\u0e29\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006823 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d \u0e1e\u0e24\u0e01\u0e29\u0e32 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c 2569-07-02 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1b\u0e34\u0e14\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 768\/104  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006840\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e34 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006840 \u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e34 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-02 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/11  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124739\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e17\u0e35.\u0e1e\u0e35.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95110\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95110\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124739 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e17\u0e35.\u0e1e\u0e35.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 95110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21 \u0e41\u0e25\u0e30 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 64\/149  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124747\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23.\u0e04\u0e32\u0e25\u0e4c\u0e21 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124747 \u0e1a\u0e08.\u0e14\u0e23.\u0e04\u0e32\u0e25\u0e4c\u0e21 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u533b\u7642\u30fb\u798f\u7949 336\/57  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e37\u0e2d\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124755\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124755 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04\u0e1e\u0e35 \u0e40\u0e25\u0e01\u0e32\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 8\/27  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e173 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124771\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e32\u0e25\u0e40\u0e1e\u0e47\u0e17\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124771 \u0e1a\u0e08.\u0e15\u0e32\u0e25\u0e40\u0e1e\u0e47\u0e17\u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 599\/560  \u0e16\u0e19\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124780\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124780 \u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 501\/185  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124798\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e25\u0e40\u0e0a\u0e48 \u0e40\u0e2d\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124798 \u0e1a\u0e08.\u0e14\u0e2d\u0e25\u0e40\u0e0a\u0e48 \u0e40\u0e2d\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e41\u0e19\u0e27 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u6559\u80b2 36\/56  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e04\u0e19\u0e18\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124801\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e25\u0e2d\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124801 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e25\u0e2d\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19  \u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 94\/35  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e23\u0e31\u0e01\u0e0b\u0e4c \u0e0b\u0e2d\u0e22 \u0e44\u0e17\u0e22\u0e23\u0e32\u0e21\u0e31\u0e0d \u0e16\u0e19\u0e19\u0e44\u0e17\u0e22\u0e23\u0e32\u0e21\u0e31\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124810\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e48\u0e32\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24109\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24109\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124810 \u0e1a\u0e08.\u0e40\u0e1b\u0e48\u0e32\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 24109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e23\u0e35\u0e14\u0e41\u0e25\u0e30\u0e2b\u0e25\u0e48\u0e2d\u0e2b\u0e25\u0e2d\u0e21\u0e42\u0e25\u0e2b\u0e30 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e01\u0e30\u0e2a\u0e35 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 32  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e2250 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124828\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e44\u0e09 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124828 \u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e44\u0e09 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e2250 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124836\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124836 \u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23  \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c  \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 1  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e1e\u0e17\u0e27\u0e35 1 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124844\",\"name_th\":\"\u0e1a\u0e08.789 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45303\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45303\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124844 \u0e1a\u0e08.789 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 45303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1214  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e04 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124879\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e2a\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46594\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46594\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124879 \u0e1a\u0e08.\u0e17\u0e2d\u0e2a\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46594 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/14  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e1733(\u0e41\u0e14\u0e07\u0e2d\u0e38\u0e14\u0e21) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124887\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e0a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124887 \u0e1a\u0e08.\u0e0b\u0e31\u0e0a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19 graphic design \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 14\/112  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 47\/2 \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 \u0e0b\u0e2d\u0e22 36 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124909\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e17\u0e23\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124909 \u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e17\u0e23\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u91d1\u878d\u30fb\u4fdd\u967a 565  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124925\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124925 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e08 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 20\/33  \u0e2d\u0e32\u0e04\u0e32\u0e23lpn\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 3 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124984\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e32\u0e25\u0e48\u0e32 \u0e41\u0e0b\u0e48 \u0e2d\u0e39\u0e4b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77400\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77400\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124984 \u0e1a\u0e08.\u0e2b\u0e21\u0e32\u0e25\u0e48\u0e32 \u0e41\u0e0b\u0e48 \u0e2d\u0e39\u0e4b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 77400 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e37\u0e48\u0e2d\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07 \u0e04\u0e39\u0e48\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e17\u0e18\u0e34 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 437  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125000\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e22\u0e01\u0e34 \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125000 \u0e1a\u0e08.\u0e42\u0e22\u0e01\u0e34 \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e19\u0e21 \u0e1c\u0e07\u0e0a\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 27\/142  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125018\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35.\u0e40\u0e2d\u0e47\u0e21. \u0e40\u0e17\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125018 \u0e1a\u0e08.\u0e08\u0e35.\u0e40\u0e2d\u0e47\u0e21. \u0e40\u0e17\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 380\/244  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e27\u0e34\u0e25\u0e25\u0e4c (\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01) \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e19\u0e19\u0e34\u0e1a\u0e32\u0e15\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125026\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e31\u0e19\u0e17\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52241\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52241\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125026 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e31\u0e19\u0e17\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 52241 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e22\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22 \u0e40\u0e01\u0e47\u0e1a\u0e23\u0e16\u0e40\u0e02\u0e47\u0e19\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e02\u0e22\u0e30 \u904b\u8f38\u30fb\u7269\u6d41 1991\/126  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125034\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e07\u0e40\u0e08\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e27\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125034 \u0e1a\u0e08.\u0e41\u0e2d\u0e07\u0e40\u0e08\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e27\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 70201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 76\/238  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e2a\u0e40\u0e0b\u0e08 \u0e16\u0e19\u0e19\u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125042\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f 5361 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125042 \u0e1a\u0e08.\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e2d\u0e1f 5361 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 290\/195  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 122 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125085\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e0b\u0e35\u0e04\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125085 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e0b\u0e35\u0e04\u0e34\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111\/259  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e3219 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e27\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125093\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e38\u0e4b\u0e22\u0e15\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125093 \u0e1a\u0e08.\u0e1b\u0e38\u0e4b\u0e22\u0e15\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e2a\u0e21 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a \u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 589  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125115\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c \u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e17\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47230\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47230\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125115 \u0e1a\u0e08.\u0e42\u0e1f\u0e23\u0e4c \u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22\u0e17\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 (\u0e01\u0e31\u0e0d\u0e0a\u0e32-\u0e01\u0e31\u0e0d\u0e0a\u0e07) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49 \u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1924  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125123\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e27\u0e32\u0e07\u0e2b\u0e23\u0e35\u0e48 \u0e40\u0e2d\u0e25\u0e34\u0e40\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125123 \u0e1a\u0e08.\u0e01\u0e27\u0e32\u0e07\u0e2b\u0e23\u0e35\u0e48 \u0e40\u0e2d\u0e25\u0e34\u0e40\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 20 \u0e41\u0e22\u0e01 11 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125140\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e27\u0e32\u0e25\u0e01\u0e49\u0e2d\u0e07\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125140 \u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e27\u0e32\u0e25\u0e01\u0e49\u0e2d\u0e07\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 161\/2  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e32 39 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125166\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e17\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125166 \u0e1a\u0e08.\u0e42\u0e17\u0e23\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e02\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/3  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 29 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125174\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125174 \u0e1a\u0e08.\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 27909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2a\u0e27\u0e34\u0e15\u0e0a\u0e4c  \u0e40\u0e1a\u0e23\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u88fd\u9020 38\/68  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e35\u0e40\u0e27\u0e48 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125182\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e27\u0e2d\u0e23\u0e34\u0e40\u0e2d\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125182 \u0e1a\u0e08.\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e27\u0e2d\u0e23\u0e34\u0e40\u0e2d\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-marketplace) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e2a\u0e19\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1a\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-payment) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (logistics) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 139  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e25\u0e39\u0e0a\u0e34\u0e1e\u0e2a\u0e4c \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 63 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125204\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e2d\u0e35 3 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125204 \u0e1a\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e2d\u0e35 3 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 35101 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e19\u0e04\u0e23\u0e2b\u0e25\u0e27\u0e07 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e01\u0e23\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e01\u0e23\u0e13\u0e35 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e23\u0e2a\u0e34\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e0b\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125247\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e44\u0e0b\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125247 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e44\u0e0b\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 838\/148  \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1e\u0e48\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125280\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e18\u0e19\u0e01\u0e21\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125280 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e18\u0e19\u0e01\u0e21\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e0b\u0e2d\u0e22 \u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 76 \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125301\",\"name_th\":\"\u0e1a\u0e08.22 \u0e27\u0e34\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125301 \u0e1a\u0e08.22 \u0e27\u0e34\u0e19\u0e40\u0e17\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47712 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/572  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125328\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2e\u0e21\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e14\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125328 \u0e1a\u0e08.\u0e42\u0e2e\u0e21\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e14\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 726 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125352\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e22\u0e32\u0e21\u0e30 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125352 \u0e1a\u0e08.\u0e42\u0e04\u0e22\u0e32\u0e21\u0e30 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e49\u0e21 \u0e1b\u0e34\u0e49\u0e07 \u0e22\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u5bbf\u6cca\u30fb\u98f2\u98df 55  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e35\u0e04\u0e2d\u0e19\u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4080 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125387\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e15\u0e15\u0e32 \u0e2b\u0e21\u0e39\u0e17\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125387 \u0e1a\u0e08.\u0e40\u0e21\u0e15\u0e15\u0e32 \u0e2b\u0e21\u0e39\u0e17\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 61\/2  \u0e0b\u0e2d\u0e22 \u0e21\u0e34\u0e15\u0e15\u0e04\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125395\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e22 \u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125395 \u0e1a\u0e08.\u0e2a\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e22 \u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e27\u0e0a \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1124  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e2526 \u0e41\u0e22\u0e016-1 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125409\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e23\u0e2a\u0e21\u0e37\u0e2d\u0e41\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125409 \u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e23\u0e2a\u0e21\u0e37\u0e2d\u0e41\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e27\u0e0a \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 14  \u0e0b\u0e2d\u0e22 \u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125433\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e04\u0e32 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125433 \u0e1a\u0e08.\u0e19\u0e32\u0e04\u0e32 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79  \u0e0b\u0e2d\u0e22 \u0e15\u0e23\u0e2d\u0e01 \u0e2b\u0e34\u0e23\u0e31\u0e0d\u0e23\u0e39\u0e08\u0e35 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125441\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e35\u0e49\u0e40\u0e04\u0e19\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125441 \u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e35\u0e49\u0e40\u0e04\u0e19\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u6559\u80b2 444  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e35 \u0e40\u0e04 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 pla.f05.d000001 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125476\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e35\u0e48\u0e40\u0e27\u0e25\u0e40\u0e1f\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125476 \u0e1a\u0e08.\u0e40\u0e27\u0e23\u0e35\u0e48\u0e40\u0e27\u0e25\u0e40\u0e1f\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e27 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e17\u0e31\u0e28\u0e19\u0e32\u0e08\u0e23 \u0e1c\u0e39\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e28\u0e32\u0e2a\u0e19\u0e01\u0e34\u0e08 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e23\u0e27\u0e21\u0e15\u0e25\u0e2d\u0e14\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e40\u0e23\u0e37\u0e2d\u0e22\u0e19\u0e15\u0e4c\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 8\/159  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e327\u0e41\u0e22\u0e014(\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e32) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125492\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e41\u0e14\u0e1b\u0e17\u0e35\u0e1f \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125492 \u0e1a\u0e08.\u0e2d\u0e30\u0e41\u0e14\u0e1b\u0e17\u0e35\u0e1f \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 295\/11  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125506\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e14\u0e34\u0e17\u0e34\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46434\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46434\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125506 \u0e1a\u0e08.\u0e42\u0e2d\u0e14\u0e34\u0e17\u0e34\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46434 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e31\u0e01\u0e29\u0e30\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e19\u0e32\u0e21 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e14\u0e47\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/193  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 29 \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125522\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e40\u0e04\u0e08\u0e35 \u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125522 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e40\u0e04\u0e08\u0e35 \u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e49\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 61  \u0e0b\u0e2d\u0e22 \u0e0a\u0e31\u0e22\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125531\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e04\u0e39\u0e13 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46592\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46592\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125531 \u0e1a\u0e08.\u0e44\u0e17\u0e04\u0e39\u0e13 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46592 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e1e\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38\/88  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125549\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35\u0e1a\u0e35 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125549 \u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35\u0e1a\u0e35 \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 9\/1  \u0e0b\u0e2d\u0e22 \u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125565\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e1e\u0e24\u0e17\u0e18\u0e34\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125565 \u0e1a\u0e08.\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e1e\u0e24\u0e17\u0e18\u0e34\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e41\u0e25\u0e30 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/72  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125581\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125581 \u0e1a\u0e08.\u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 36  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e301 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125638\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125638 \u0e1a\u0e08.\u0e1f\u0e47\u0e2d\u0e01\u0e0b\u0e4c \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 (visa) \u0e15\u0e48\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e39\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e07\u0e2a\u0e38\u0e25\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 498\/98  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125662\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e08\u0e2b\u0e32\u0e0d \u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"60203\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"60203\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125662 \u0e1a\u0e08.\u0e2d\u0e32\u0e08\u0e2b\u0e32\u0e0d \u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 60203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e33\u0e0a\u0e48\u0e2d\u0e07\u0e22\u0e39\u0e17\u0e39\u0e1b \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u60c5\u5831\u901a\u4fe1\u30fbit 12\/2  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 119 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125689\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125689 \u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e27\u0e0a \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 116\/10  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e2524 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021735\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e17\u0e40\u0e17\u0e47\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021735 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e17\u0e40\u0e17\u0e47\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 197\/148  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e21\u0e2b\u0e32\u0e0a\u0e31\u0e22 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021751\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04-\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e17\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021751 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04-\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e17\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 222\/153  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021760\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021760 \u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 18\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021778\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e2e\u0e32\u0e15\u0e30 \u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021778 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e2e\u0e32\u0e15\u0e30 \u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 43301 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2a\u0e15\u0e34\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e1d\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 - \u0e2a\u0e48\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u5efa\u8a2d 156\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021794\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021794 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19 \u5efa\u8a2d 223\/121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021824\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e01\u0e23\u0e32\u0e1f \u0e40\u0e08\u0e41\u0e1b\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021824 \u0e1a\u0e08.\u0e42\u0e01\u0e01\u0e23\u0e32\u0e1f \u0e40\u0e08\u0e41\u0e1b\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 113 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021841\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e41\u0e19\u0e1b \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021841 \u0e1a\u0e08.\u0e2a\u0e41\u0e19\u0e1b \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e14\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021859\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021859 \u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e25\u0e39\u0e01\u0e01\u0e25\u0e34\u0e49\u0e07\u0e23\u0e35\u0e14\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e01\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1e\u0e47\u0e04\u0e16\u0e38\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e16\u0e38\u0e07\u0e41\u0e1e\u0e47\u0e04\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e02\u0e19\u0e01\u0e25 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e1e\u0e47\u0e04\u0e16\u0e38\u0e07\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 129\/272  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021867\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e1f\u0e42\u0e1f\u0e01\u0e32\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021867 \u0e1a\u0e08.\u0e2d\u0e31\u0e1f\u0e42\u0e1f\u0e01\u0e32\u0e42\u0e15\u0e49 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021875\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35.\u0e40\u0e2d\u0e1f.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021875 \u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35.\u0e40\u0e2d\u0e1f.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 353\/121  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021891\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e34\u0e0d \u0e42\u0e0b\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021891 \u0e1a\u0e08.\u0e23\u0e34\u0e0d \u0e42\u0e0b\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021913\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e35\u0e4b\u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46312\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46312\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021913 \u0e1a\u0e08.\u0e15\u0e35\u0e4b\u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46312 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32\u0e41\u0e2b\u0e49\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32\u0e17\u0e2d\u0e14 \u0e01\u0e23\u0e30\u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e32\u0e2a\u0e14 \u0e1b\u0e25\u0e32\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 280\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024700\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024700 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u60c5\u5831\u901a\u4fe1\u30fbit 89\/248  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e40\u0e1e\u0e25\u0e2a4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024718\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024718 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 87301 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30\u0e1e\u0e36\u0e07\u0e1e\u0e34\u0e07 \u533b\u7642\u30fb\u798f\u7949 129\/128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024726\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e19\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024726 \u0e1a\u0e08.\u0e19\u0e31\u0e19\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024734\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e1f\u0e34\u0e2a\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86902\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86902\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024734 \u0e1a\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e1f\u0e34\u0e2a\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 86902 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u533b\u7642\u30fb\u798f\u7949 110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024742\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e27 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024742 \u0e1a\u0e08.\u0e19\u0e32\u0e27 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar energy system) \u0e41\u0e1c\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002216\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32289\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002216 \u0e2b\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32289 2569-07-02 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e31\u0e01\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020500\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e13\u0e35\u0e2b\u0e21\u0e39\u0e2a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020500 \u0e1a\u0e08.\u0e1b\u0e23\u0e32\u0e13\u0e35\u0e2b\u0e21\u0e39\u0e2a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 147\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020542\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04   \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020542 \u0e1a\u0e08.\u0e22\u0e39\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04   \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 78109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1\/31  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 63\/1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020551\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1a\u0e23\u0e2d\u0e14\u0e41\u0e04\u0e2a\u0e15\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020551 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1a\u0e23\u0e2d\u0e14\u0e41\u0e04\u0e2a\u0e15\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 77\/296  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0195569002421\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e21\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002421 \u0e1a\u0e08.\u0e0a\u0e21\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002439\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e2d\u0e35 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002439 \u0e1a\u0e08.\u0e17\u0e35 \u0e2d\u0e35 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 10, 12  \u0e0b\u0e2d\u0e22 \u0e40\u0e1b\u0e49\u0e32\u0e17\u0e2d\u0e07\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002762\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e31\u0e1b\u0e15\u0e31\u0e19\u0e1e\u0e25\u0e31\u0e2a 6395 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002762 \u0e2b\u0e08.\u0e01\u0e31\u0e1b\u0e15\u0e31\u0e19\u0e1e\u0e25\u0e31\u0e2a 6395 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-02 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 1001\/168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034933\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034933 \u0e1a\u0e08.\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2b\u0e21\u0e39\u0e1b\u0e34\u0e49\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034941\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e2a\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034941 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e2a\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e02\u0e31\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e40\u0e2e\u0e35\u0e4a\u0e22\u0e1a \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e02\u0e38\u0e14 \u0e23\u0e16\u0e15\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 638\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034968\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e25\u0e35\u0e40\u0e0b\u0e35\u0e22\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e01\u0e15\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034968 \u0e1a\u0e08.\u0e2d\u0e25\u0e35\u0e40\u0e0b\u0e35\u0e22\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e01\u0e15\u0e4c \u0e0a\u0e32\u0e23\u0e4c\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 35101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 145\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034976\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e28\u0e23\u0e32\u0e04\u0e33 \u0e08\u0e31\u0e01\u0e23\u0e01\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034976 \u0e1a\u0e08.\u0e1a\u0e38\u0e28\u0e23\u0e32\u0e04\u0e33 \u0e08\u0e31\u0e01\u0e23\u0e01\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e15\u0e39\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u88fd\u9020 39\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034984\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e0a\u0e17\u0e35974 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034984 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e0a\u0e17\u0e35974 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 62\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035000\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e25\u0e32\u0e22\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035000 \u0e1a\u0e08.\u0e2d\u0e25\u0e32\u0e22\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035018\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e19\u0e34\u0e18 \u0e44\u0e18\u0e23\u0e1f\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035018 \u0e1a\u0e08.\u0e0b\u0e35\u0e19\u0e34\u0e18 \u0e44\u0e18\u0e23\u0e1f\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 82199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e08\u0e14\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14  \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e27\u0e35\u0e0b\u0e48\u0e32(visa) \u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e17\u0e33\u0e07\u0e32\u0e19 (work permit)  \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e37\u0e48\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e32\u0e17\u0e34\u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21  \u0e01\u0e23\u0e21\u0e2a\u0e23\u0e23\u0e1e\u0e32\u0e01\u0e23  \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 3\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035042\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035042 \u0e1a\u0e08.\u0e1a\u0e35\u0e0b\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u5efa\u8a2d 127\/737  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035085\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e2a \u0e23\u0e35\u0e44\u0e0b\u0e04\u0e25\u0e34\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035085 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e2a \u0e23\u0e35\u0e44\u0e0b\u0e04\u0e25\u0e34\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46622 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32 \u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e01\u0e48\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001154\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e39\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001154 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e19\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e39\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-02 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32  \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14  \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008843\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008843 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 22199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e08\u0e32\u0e01\u0e22\u0e32\u0e07 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 111\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008851\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e32\u0e0d\u0e41\u0e2a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008851 \u0e1a\u0e08.\u0e09\u0e32\u0e0d\u0e41\u0e2a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 31\/29  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e19\u0e34\u0e22\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008860\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e19\u0e01\u0e20\u0e23\u0e13\u0e4c \u0e27\u0e34\u0e19 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008860 \u0e1a\u0e08.\u0e01\u0e19\u0e01\u0e20\u0e23\u0e13\u0e4c \u0e27\u0e34\u0e19 \u0e40\u0e17\u0e04 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e27\u0e32\u0e25\u0e4c\u0e27\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e42\u0e23\u0e07\u0e01\u0e25\u0e31\u0e48\u0e19\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 19\/119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008878\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e44\u0e0a\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008878 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e44\u0e0a\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e01\u0e2d\u0e41\u0e1a\u0e1a\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e44\u0e2d\u0e17\u0e35  \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e1a\u0e19\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d  \u0e41\u0e25\u0e30\u0e40\u0e27\u0e1b\u0e44\u0e0b\u0e15\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 101\/59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002098\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35.\u0e0b\u0e35.\u0e41\u0e2d\u0e25. \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002098 \u0e1a\u0e08.\u0e1a\u0e35.\u0e0b\u0e35.\u0e41\u0e2d\u0e25. \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46313 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d - \u0e02\u0e32\u0e22 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 145\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003566\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e21.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e21\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003566 \u0e1a\u0e08.\u0e1e\u0e35.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e21.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e21\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23  \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 23\/4\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569006874\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e15\u0e30\u0e40\u0e1e\u0e47\u0e17 \u0e40\u0e2d\u0e47\u0e21\u0e44\u0e1e\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006874 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e15\u0e30\u0e40\u0e1e\u0e47\u0e17 \u0e40\u0e2d\u0e47\u0e21\u0e44\u0e1e\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e41\u0e21\u0e27 \u0e04\u0e32\u0e40\u0e1f\u0e48\u0e41\u0e21\u0e27 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e21\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e15\u0e31\u0e14\u0e02\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 517\/139  \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e-\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006882\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e34\u0e15 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11011\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11011\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006882 \u0e1a\u0e08.\u0e08\u0e34\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e34\u0e15 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 11011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e38\u0e23\u0e32\u0e01\u0e25\u0e31\u0e48\u0e19 \u0e2a\u0e38\u0e23\u0e32\u0e41\u0e0a\u0e48 \u0e2a\u0e38\u0e23\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19  \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u88fd\u9020 193  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e2d\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e14 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006891\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e04.\u0e17\u0e35 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006891 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e04.\u0e17\u0e35 \u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32\u0e42\u0e19\u0e27\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 688\/53  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e-\u0e42\u0e04\u0e23\u0e01\u0e23\u0e27\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0335569001091\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e27\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001091 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e27\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0335569001104\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001104 \u0e1a\u0e08.\u0e2a\u0e34\u0e19\u0e17\u0e2d\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0393569000319\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e35\u0e48\u0e40\u0e01\u0e25\u0e2d \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000319 \u0e2b\u0e08.\u0e2a\u0e35\u0e48\u0e40\u0e01\u0e25\u0e2d \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 2569-07-02 1000000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0395569000418\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000418 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0405569006296\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d \u0e1a\u0e2d\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006296 \u0e1a\u0e08.\u0e44\u0e2d \u0e1a\u0e2d\u0e22\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 (food truck\/food cart) \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 924  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 \u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e4a\u0e2d\u0e01\u0e19\u0e49\u0e2d\u0e22-\u0e1a\u0e49\u0e32\u0e19\u0e42\u0e04\u0e01\u0e1f\u0e31\u0e19\u0e42\u0e1b\u0e07 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006326\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e191956 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006326 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e191956 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006334\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e28\u0e23\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006334 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e28\u0e23\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e17\u0e35\u0e48 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5efa\u8a2d 319  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003424\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e25\u0e2d\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003424 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e25\u0e2d\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 69100 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e2f\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 593  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0425569000506\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e15\u0e0b\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000506 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e15\u0e0b\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 41001 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e23\u0e27\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e39\u0e07 \u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e14\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 16\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0443569000687\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d99 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000687 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d99 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-02 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5efa\u8a2d 6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001596\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e40\u0e22\u0e2d\u0e23\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23953\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23953\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001596 \u0e1a\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e40\u0e22\u0e2d\u0e23\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 23953 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1c\u0e2a\u0e21\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e1e\u0e37\u0e49\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u88fd\u9020 322  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0445569001600\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e19\u0e17\u0e23 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01500\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01500\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001600 \u0e1a\u0e08.\u0e01\u0e31\u0e19\u0e17\u0e23 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 01500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u8fb2\u6797\u6c34\u7523 162\/2  \u0e16\u0e19\u0e19\u0e08\u0e38\u0e11\u0e32\u0e07\u0e01\u0e39\u0e23 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0473569000857\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e18\u0e19\u0e42\u0e0a\u0e15\u0e34 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000857 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e18\u0e19\u0e42\u0e0a\u0e15\u0e34 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 2569-07-02 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0495569000506\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e23\u0e31\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47733\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47733\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000506 \u0e1a\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e23\u0e31\u0e01\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47733 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u0e44\u0e21\u0e49\u0e14\u0e2d\u0e01 \u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e44\u0e21\u0e49\u0e25\u0e49\u0e2d\u0e21 \u0e44\u0e21\u0e49\u0e02\u0e38\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1e\u0e37\u0e0a\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569014891\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e40\u0e1b\u0e48\u0e32 \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014891 \u0e1a\u0e08.\u0e1f\u0e39\u0e48\u0e40\u0e1b\u0e48\u0e32 \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 197\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014913\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58192\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58192\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014913 \u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e34\u0e01\u0e0b\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 58192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content) \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23 (affiliate marketing) \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0b\u0e35\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u60c5\u5831\u901a\u4fe1\u30fbit 169\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014921\",\"name_th\":\"\u0e1a\u0e08.\u0e0a.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014921 \u0e1a\u0e08.\u0e0a.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e49\u0e32\u0e27\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e02\u0e49\u0e32\u0e27 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014948\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2e\u0e34\u0e25\u0e25\u0e4c\u0e44\u0e0b\u0e14\u0e4c \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014948 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2e\u0e34\u0e25\u0e25\u0e4c\u0e44\u0e0b\u0e14\u0e4c \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 33\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014964\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014964 \u0e1a\u0e08.\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 43\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014972\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014972 \u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17            \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (e-commerce)            \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014999\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1e\u0e34\u0e25 \u0e14\u0e35 \u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10802\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10802\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014999 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1e\u0e34\u0e25 \u0e14\u0e35 \u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 10802 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1c\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e17\u0e33 \u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e01\u0e25\u0e1a \u0e23\u0e33\u0e02\u0e49\u0e32\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e49\u0e32\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30 \u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u88fd\u9020 335  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000678\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e17\u0e2d\u0e07 481\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0513569000678 \u0e2b\u0e08.\u0e1a\u0e31\u0e19\u0e44\u0e14\u0e17\u0e2d\u0e07 481 2569-07-02 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/1190  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0513569000686\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e15\u0e48\u0e07\u0e41\u0e23\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0513569000686 \u0e2b\u0e08.\u0e41\u0e15\u0e48\u0e07\u0e41\u0e23\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-02 1000000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/1190  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001528\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e34\u0e28\u0e18\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66192\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66192\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001528 \u0e1a\u0e08.\u0e17\u0e34\u0e28\u0e18\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 66192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e15\u0e39\u0e49\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001536\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e1e\u0e34\u0e21\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001536 \u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\u0e1e\u0e34\u0e21\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e22\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001544\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e42\u0e23\u0e25 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001544 \u0e1a\u0e08.\u0e1a\u0e35 \u0e42\u0e23\u0e25 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 59111 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e1b\u0e23\u0e32\u0e01\u0e0e\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e20\u0e32\u0e1e\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e09\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e08\u0e2d\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e43\u0e19\u0e41\u0e1e\u0e25\u0e14\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e43\u0e19\u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e \u60c5\u5831\u901a\u4fe1\u30fbit 232\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001552\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e23\u0e27\u0e22\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001552 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e23\u0e27\u0e22\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e1f\u0e25\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 310  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001561\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001561 \u0e1a\u0e08.\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49\u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e15\u0e25\u0e32\u0e14 \u0e41\u0e1c\u0e07\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 888\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002018\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e49\u0e32\u0e22\u0e2a\u0e27\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002018 \u0e2b\u0e08.\u0e2d\u0e49\u0e32\u0e22\u0e2a\u0e27\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-02 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004292\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e22\u0e2a\u0e4c \u0e04\u0e2d\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e15\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004292 \u0e1a\u0e08.\u0e2d\u0e32\u0e22\u0e2a\u0e4c \u0e04\u0e2d\u0e19\u0e17\u0e23\u0e32\u0e2a\u0e15\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 (integrated marketing communication) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 323\/127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0585569000246\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e44\u0e15 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52109\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52109\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\",\"province_ja\":\"\u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\",\"search_text\":\"0585569000246 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e44\u0e15 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 52109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e19\u0e15\u0e32\u0e21\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 177  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0603569001436\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e17\u0e35\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001436 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e17\u0e35 2569-07-02 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0603569001444\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001444 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 2569-07-02 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569001900\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001900 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 71102 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 71\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e2a\u0e31\u0e19\u0e04\u0e39-\u0e27\u0e31\u0e07\u0e44\u0e1c\u0e48 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0615569000440\",\"name_th\":\"\u0e1a\u0e08.\u0e0a.168 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000440 \u0e1a\u0e08.\u0e0a.168 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1b\u0e23\u0e38\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e27\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 25\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0625569000750\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85493\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85493\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0625569000750 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 85493 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2a\u0e2d\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e27\u0e34\u0e0a\u0e32\u0e04\u0e13\u0e34\u0e15\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 \u0e2f\u0e25\u0e2f \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e16\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19 \u6559\u80b2 110\/1  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2b\u0e23\u0e23\u0e29\u0e32 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0635569001381\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e44\u0e2d \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001381 \u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e44\u0e2d \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 9\/35  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e14\u0e33\u0e2b\u0e23\u0e34 1 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0675569001403\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e04\u0e21\u0e1b\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e40\u0e02\u0e32\u0e04\u0e49\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001403 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e04\u0e21\u0e1b\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e40\u0e02\u0e32\u0e04\u0e49\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 85\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003031\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003031 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 213\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003049\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e16\u0e36\u0e07\u0e40\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003049 \u0e1a\u0e08.\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e16\u0e36\u0e07\u0e40\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1a\u0e27\u0e0a \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002433\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002433 \u0e1a\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e40\u0e2d\u0e01\u0e0a\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 68  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0745569006986\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569006986 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e21\u0e2b\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e04\u0e49\u0e01 \u0e27\u0e38\u0e49\u0e19 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 438\/185  \u0e16\u0e19\u0e19\u0e14\u0e2d\u0e19\u0e44\u0e01\u0e48\u0e14\u0e35 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0765569001399\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e48\u0e2d\u0e25\u0e32\u0e20 456 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01469\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01469\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001399 \u0e1a\u0e08.\u0e15\u0e48\u0e2d\u0e25\u0e32\u0e20 456 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 01469 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e32\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e01\u0e48\u0e0a\u0e19 \u0e44\u0e01\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 1\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0805569002505\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002505 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/1-2  \u0e16\u0e19\u0e19\u0e19\u0e34\u0e01\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002513\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e1e\u0e23\u0e30\u0e1e\u0e23\u0e2b\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002513 \u0e1a\u0e08.\u0e1e\u0e23\u0e1e\u0e23\u0e30\u0e1e\u0e23\u0e2b\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 92  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0825569001061\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c 268 \u0e1b\u0e34\u0e42\u0e15\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001061 \u0e1a\u0e08.\u0e2a\u0e1b\u0e35\u0e14 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c 268 \u0e1b\u0e34\u0e42\u0e15\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 201  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569012357\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43901\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43901\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012357 \u0e1a\u0e08.\u0e40\u0e04.\u0e1e\u0e35.\u0e40\u0e2d\u0e2a. \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 43901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e01\u0e40\u0e2a\u0e32\u0e40\u0e02\u0e47\u0e21 \u5efa\u8a2d 119\/112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012403\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e25\u0e2a\u0e40\u0e17\u0e35\u0e22 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012403 \u0e1a\u0e08.\u0e40\u0e0b\u0e40\u0e25\u0e2a\u0e40\u0e17\u0e35\u0e22 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 3\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0903569001441\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e39\u0e48\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001441 \u0e2b\u0e08.\u0e2d\u0e39\u0e48\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 2569-07-02 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e0a\u0e48\u0e19 \u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e35\u0e49 \u0e15\u0e34\u0e4a\u0e01\u0e15\u0e4a\u0e2d\u0e01 \u0e25\u0e32\u0e0b\u0e32\u0e14\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 125\/740  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005236\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35-\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005236 \u0e1a\u0e08.\u0e08\u0e35-\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1406\/3  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0943569000232\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e32\u0e27\u0e44\u0e23\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0943569000232 \u0e2b\u0e08.\u0e0a\u0e32\u0e27\u0e44\u0e23\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 2569-07-02 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0b\u0e36\u0e48\u0e07\u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a\u0e14\u0e34\u0e1a \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 57\/77  \u0e0b\u0e2d\u0e22 \u0e1b\u0e32\u0e01\u0e19\u0e49\u0e3319 \u0e16\u0e19\u0e19\u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0943569000241\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e04\u0e25\u0e32\u0e2a \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0943569000241 \u0e2b\u0e08.\u0e2d\u0e34\u0e04\u0e25\u0e32\u0e2a \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 2569-07-02 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 314  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0955569000480\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000480 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/203  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 \u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 19\/1 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0955569000498\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000498 \u0e1a\u0e08.\u0e40\u0e04.\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\/\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e04\u0e32\u0e23\/\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e0b\u0e48\u0e2d\u0e21 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e28\u0e32\u0e2a\u0e19\u0e2a\u0e16\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e43\u0e19\u0e23\u0e48\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e43\u0e19\u0e23\u0e48\u0e21 \u0e42\u0e23\u0e07\u0e22\u0e34\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e43\u0e19\u0e23\u0e48\u0e21\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e42\u0e23\u0e07\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e23\u0e37\u0e2d \u0e25\u0e32\u0e19\u0e19\u0e4d\u0e49\u0e32\u0e41\u0e02\u0e47\u0e07 \u0e2f\u0e25\u0e2f \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47\u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e2d\u0e14\u0e23\u0e16 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e40\u0e14\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e30\u0e42\u0e1a\u0e23\u0e32\u0e13\u0e2a\u0e16\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 153\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0963569000267\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e32\u0e2d\u0e35\u0e0b\u0e39 \u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e04\u0e0b\u0e40\u0e0a\u0e19\u0e08\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66123\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66123\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000267 \u0e2b\u0e08.\u0e1f\u0e32\u0e2d\u0e35\u0e0b\u0e39 \u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e04\u0e0b\u0e40\u0e0a\u0e19\u0e08 2569-07-02 1000000 66123 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28(\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u91d1\u878d\u30fb\u4fdd\u967a 392  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0963569000275\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e35\u0e14\u0e32 \u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e04\u0e0b\u0e40\u0e0a\u0e19\u0e08\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66123\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66123\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000275 \u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e35\u0e14\u0e32 \u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e40\u0e2d\u0e47\u0e04\u0e0b\u0e40\u0e0a\u0e19\u0e08 2569-07-02 1000000 66123 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e42\u0e14\u0e22\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e07\u0e34\u0e19\u0e15\u0e23\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28(\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u91d1\u878d\u30fb\u4fdd\u967a 656\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569006513\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e27\u0e2a\u0e4c\u0e0b\u0e35\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006513 \u0e2b\u0e08.\u0e44\u0e27\u0e2a\u0e4c\u0e0b\u0e35\u0e1f\u0e32\u0e21 2569-07-01 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/10  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006521\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e31\u0e27\u0e2b\u0e2d\u0e21 \u0e2a\u0e22\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006521 \u0e2b\u0e08.\u0e2b\u0e31\u0e27\u0e2b\u0e2d\u0e21 \u0e2a\u0e22\u0e32\u0e21 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006530\",\"name_th\":\"\u0e2b\u0e08.\u0e1c\u0e31\u0e01\u0e22\u0e01\u0e2a\u0e27\u0e19\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006530 \u0e2b\u0e08.\u0e1c\u0e31\u0e01\u0e22\u0e01\u0e2a\u0e27\u0e19 2569-07-01 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006548\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e0a\u0e31\u0e22\u0e0b\u0e35\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006548 \u0e2b\u0e08.\u0e27\u0e34\u0e0a\u0e31\u0e22\u0e0b\u0e35\u0e1f\u0e32\u0e21 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006556\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006556 \u0e2b\u0e08.\u0e0b\u0e35\u0e0b\u0e35\u0e1f\u0e32\u0e21 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006564\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e1e\u0e34\u0e25 \u0e40\u0e2d\u0e08\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006564 \u0e2b\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e1e\u0e34\u0e25 \u0e40\u0e2d\u0e08 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006572\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e08 \u0e17\u0e23\u0e35\u0e1e\u0e25\u0e31\u0e2a\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006572 \u0e2b\u0e08.\u0e40\u0e2d\u0e08 \u0e17\u0e23\u0e35\u0e1e\u0e25\u0e31\u0e2a\u0e1f\u0e32\u0e21 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/10  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006581\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e08\u0e35\u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006581 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e40\u0e2d\u0e08\u0e35\u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 2569-07-01 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 . \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006599\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e21\u0e2a\u0e42\u0e23\u0e23\u0e35\u0e48\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006599 \u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e21\u0e2a\u0e42\u0e23\u0e23\u0e35\u0e48 2569-07-01 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006602\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\u0e01\u0e23\u0e35\u0e19\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006602 \u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\u0e01\u0e23\u0e35\u0e19 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e0b\u0e2d\u0e22 . \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006611\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006611 \u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\u0e1f\u0e32\u0e21 2569-07-01 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006629\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006629 \u0e2b\u0e08.\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a 2569-07-01 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e0b\u0e2d\u0e22 . \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006637\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e27\u0e35\u0e0b\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006637 \u0e2b\u0e08.\u0e40\u0e2d\u0e27\u0e35\u0e0b\u0e1f\u0e32\u0e21 2569-07-01 1000000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006645\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e01\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006645 \u0e2b\u0e08.\u0e41\u0e2d\u0e01\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1f\u0e32\u0e21 2569-07-01 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/10  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006653\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e0b\u0e35\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006653 \u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e0b\u0e35\u0e1f\u0e32\u0e21 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269\/239  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006661\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006661 \u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1f\u0e32\u0e21 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/10  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006670\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e34\u0e25\u0e14\u0e4c\u0e2a\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006670 \u0e2b\u0e08.\u0e40\u0e1f\u0e23\u0e0a\u0e1f\u0e34\u0e25\u0e14\u0e4c\u0e2a\u0e1f\u0e32\u0e21 2569-07-01 1000000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/10  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006688\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e42\u0e01\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006688 \u0e2b\u0e08.\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e42\u0e01\u0e1f\u0e32\u0e21 2569-07-01 1000000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/10  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006696\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2e\u0e34\u0e25\u0e2a\u0e4c\u0e1f\u0e32\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006696 \u0e2b\u0e08.\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2e\u0e34\u0e25\u0e2a\u0e4c\u0e1f\u0e32\u0e21 2569-07-01 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/10  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006700\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e27\u0e32 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006700 \u0e2b\u0e08.\u0e19\u0e32\u0e27\u0e32 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c 2569-07-01 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e21\u0e25\u0e07\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 485  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006718\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e07 \u0e15\u0e4b\u0e07 \u0e15\u0e34\u0e48\u0e21\u0e0b\u0e48\u0e33\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10751\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10751\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006718 \u0e2b\u0e08.\u0e15\u0e07 \u0e15\u0e4b\u0e07 \u0e15\u0e34\u0e48\u0e21\u0e0b\u0e48\u0e33 2569-07-01 1000000 10751 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 242\/250  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e1582 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006726\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e2e\u0e32\u0e23\u0e4c\u0e40\u0e27\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006726 \u0e2b\u0e08.\u0e2d\u0e30\u0e42\u0e01\u0e23\u0e2e\u0e32\u0e23\u0e4c\u0e40\u0e27\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-01 1000000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 466\/9  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569006734\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d \u0e2d\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006734 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d \u0e2d\u0e2d\u0e25 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-01 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123708\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e17\u0e35\u0e1f \u0e04\u0e2d\u0e19\u0e0b\u0e39\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123708 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e17\u0e35\u0e1f \u0e04\u0e2d\u0e19\u0e0b\u0e39\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7,9,11,13,15  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 6 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123716\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e0b\u0e32\u0e23\u0e35\u0e48 \u0e27\u0e34\u0e25\u0e42\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123716 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e0b\u0e32\u0e23\u0e35\u0e48 \u0e27\u0e34\u0e25\u0e42\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\/\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 696\/93  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e38\u0e13\u0e32\u0e25\u0e31\u0e22 \u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123724\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123724 \u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102\/83  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e32\u0e19\u0e35 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123732\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e32\u0e42\u0e19\u0e27\u0e32\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123732 \u0e1a\u0e08.\u0e08\u0e32\u0e42\u0e19\u0e27\u0e32\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 62023 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e04\u0e49\u0e14\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c  \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u60c5\u5831\u901a\u4fe1\u30fbit 49\/149  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2a\u0e19\u0e32\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e21.9 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123741\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e40\u0e08\u0e49\u0e08\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123741 \u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e40\u0e08\u0e49\u0e08\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 137  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123759\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10772\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10772\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123759 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 10772 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e2a\u0e15\u0e48\u0e32\u0e07\u0e46 \u88fd\u9020 21\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e34\u0e49\u0e19\u0e17\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 401-404 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123783\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123783 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 337  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 4 \u0e0b\u0e2d\u0e22 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123791\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e34\u0e42\u0e2d \u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123791 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e34\u0e42\u0e2d \u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e25\u0e32\u0e01\u0e08\u0e39\u0e07 \u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 12\/1  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123805\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123805 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 10\/240  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 73 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123856\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123856 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e23\u0e19\u0e14\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e01\u0e34\u0e4a\u0e1f\u0e0a\u0e49\u0e2d\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/15  \u0e0b\u0e2d\u0e22 \u0e1e\u0e36\u0e48\u0e07\u0e21\u0e3550 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123864\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 10 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123864 \u0e1a\u0e08.\u0e17\u0e35 10 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e2d\u0e40\u0e21\u0e0b\u0e2d\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e21\/\u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\/ \u0e2a\u0e21\u0e39\u0e17\u0e15\u0e35\u0e49 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e04\u0e49\u0e01 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 265  \u0e16\u0e19\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123929\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e04\u0e32\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123929 \u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e04\u0e32\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 23\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123937\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123937 \u0e1a\u0e08.\u0e41\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122  \u0e0b\u0e2d\u0e22 \u0e01\u0e33\u0e19\u0e31\u0e19\u0e41\u0e21\u0e49\u0e19 13 \u0e41\u0e22\u0e01 33 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123953\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123953 \u0e1a\u0e08.\u0e2d\u0e35\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 643\/6  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 103 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123961\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e27\u0e32\u0e42\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123961 \u0e1a\u0e08.\u0e2d\u0e30\u0e27\u0e32\u0e42\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 99\/43  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 29 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123970\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e17\u0e15\u0e35\u0e49 \u0e1a\u0e2d\u0e25\u0e19\u0e35\u0e48 \u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123970 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e17\u0e15\u0e35\u0e49 \u0e1a\u0e2d\u0e25\u0e19\u0e35\u0e48 \u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 8\/298  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 85 \u0e16\u0e19\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123988\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e04\u0e1a\u0e2d\u0e01\u0e0b\u0e4c \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123988 \u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e04\u0e1a\u0e2d\u0e01\u0e0b\u0e4c \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 22220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e21\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e42\u0e14\u0e22\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e0b\u0e34\u0e1b \u0e01\u0e23\u0e30\u0e14\u0e38\u0e21 \u0e40\u0e0a\u0e37\u0e2d\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e35 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 149  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 43\/1 (\u0e04\u0e38\u0e13\u0e2b\u0e0d\u0e34\u0e07\u0e40\u0e08\u0e37\u0e2d) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124046\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124046 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 45101 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e31\u0e2a \u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e27\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e27\u0e35(ngv) \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e25\u0e1e\u0e35\u0e08\u0e35(lpg) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e15\u0e48\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 283  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 42 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124062\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e1e\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124062 \u0e1a\u0e08.\u0e2d\u0e31\u0e1e\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e19\u0e17\u0e4c\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 47\/148  \u0e0b\u0e2d\u0e22 \u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 3\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124097\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e01\u0e34\u0e19\u0e2a\u0e4c \u0e1f\u0e32\u0e27\u0e19\u0e4c\u0e14\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124097 \u0e1a\u0e08.\u0e1a\u0e35\u0e01\u0e34\u0e19\u0e2a\u0e4c \u0e1f\u0e32\u0e27\u0e19\u0e4c\u0e14\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30 ai \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30 ai \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u60c5\u5831\u901a\u4fe1\u30fbit 92  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e40\u0e0b\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124119\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e40\u0e25\u0e32\u0e19\u0e08\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85423\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85423\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124119 \u0e1a\u0e08.\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e40\u0e25\u0e32\u0e19\u0e08\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 85423 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u6559\u80b2 898\/31-32  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e2a\u0e27\u0e35 \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c 2  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e40\u0e2d\u0e2a-09 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 19 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124127\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e2d\u0e23\u0e48\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124127 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e2d\u0e23\u0e48\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/358  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 150 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124135\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e23\u0e4c\u0e27\u0e35\u0e15\u0e49\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124135 \u0e1a\u0e08.\u0e41\u0e04\u0e23\u0e4c\u0e27\u0e35\u0e15\u0e49\u0e32 \u0e40\u0e2e\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/252  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e31\u0e13\u0e11\u0e19\u0e32-\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e34\u0e15\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e22\u0e01 10 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124143\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e19\u0e40\u0e2d\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124143 \u0e1a\u0e08.\u0e22\u0e39\u0e42\u0e19\u0e40\u0e2d\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c            \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 463\/5  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27101(\u0e27\u0e31\u0e14\u0e1a\u0e36\u0e07\u0e17\u0e2d\u0e07\u0e2b\u0e25\u0e32\u0e07) \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124160\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124160 \u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21\u0e2b\u0e25\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e07\u0e34\u0e19 \u0e19\u0e32\u0e01 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e27\u0e31\u0e15\u0e16\u0e38\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e01\u0e29\u0e32\u0e1b\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 306  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e34\u0e28\u0e32\u0e25 \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124194\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e47\u0e2d\u0e01\u0e41\u0e21\u0e19 \u0e41\u0e2d\u0e25\u0e44\u0e25\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124194 \u0e1a\u0e08.\u0e25\u0e47\u0e2d\u0e01\u0e41\u0e21\u0e19 \u0e41\u0e2d\u0e25\u0e44\u0e25\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 68  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a6 \u0e16\u0e19\u0e19\u0e19\u0e32\u0e04\u0e19\u0e34\u0e27\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124216\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e2e\u0e31\u0e1a \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124216 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e2e\u0e31\u0e1a \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 82302 \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 596\/7  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124232\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e07\u0e2e\u0e35\u0e49 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124232 \u0e1a\u0e08.\u0e0b\u0e31\u0e07\u0e2e\u0e35\u0e49 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u4e0d\u52d5\u7523 341  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e16\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124259\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e0b\u0e42\u0e01\u0e23\u0e4c\u0e27 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124259 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e0b\u0e42\u0e01\u0e23\u0e4c\u0e27 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e25\u0e39\u0e01\u0e01\u0e27\u0e32\u0e14 \u0e0a\u0e47\u0e2d\u0e01\u0e42\u0e01\u0e41\u0e25\u0e15 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e40\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e23.\u0e59 \u0e0b\u0e2d\u0e22 14 \u0e40\u0e40\u0e22\u0e01 18 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124267\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124267 \u0e1a\u0e08.\u0e27\u0e34\u0e2a\u0e14\u0e2d\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 62012 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e23\u0e4c\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u60c5\u5831\u901a\u4fe1\u30fbit 288\/29  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124275\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e22 \u0e23\u0e27\u0e22 \u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47895\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47895\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124275 \u0e1a\u0e08.\u0e2a\u0e27\u0e22 \u0e23\u0e27\u0e22 \u0e44\u0e23\u0e49\u0e02\u0e35\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47895 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0772 \u0e41\u0e22\u0e012 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124291\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124291 \u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 34\/23  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e40\u0e0a\u0e34\u0e14\u0e0a\u0e39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124321\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124321 \u0e1a\u0e08.\u0e44\u0e27\u0e23\u0e48\u0e32 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34\/23  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e39 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124330\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e22\u0e4c \u0e40\u0e2d\u0e21\u0e34\u0e40\u0e19\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124330 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e22\u0e4c \u0e40\u0e2d\u0e21\u0e34\u0e40\u0e19\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 75  \u0e16\u0e19\u0e19\u0e14\u0e34\u0e19\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124356\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e08\u0e43\u0e08\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124356 \u0e1a\u0e08.\u0e43\u0e08\u0e43\u0e08\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 162\/16   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2741 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124364\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124364 \u0e1a\u0e08.\u0e21\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2823\/3  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124372\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2a\u0e40\u0e1b\u0e23\u0e32\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124372 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2a\u0e40\u0e1b\u0e23\u0e32\u0e17\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19  \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 478,480  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124381\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e27\u0e19\u0e2d\u0e34\u0e21 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e32\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124381 \u0e1a\u0e08.\u0e01\u0e27\u0e19\u0e2d\u0e34\u0e21 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e32\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/43  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 29 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124411\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e34\u0e1e\u0e22\u0e27\u0e23\u0e23\u0e13 \u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124411 \u0e1a\u0e08.\u0e17\u0e34\u0e1e\u0e22\u0e27\u0e23\u0e23\u0e13 \u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/178  \u0e16\u0e19\u0e19\u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e1a\u0e32\u0e07\u0e04\u0e49\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124429\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e2d\u0e35 1 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124429 \u0e1a\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e2d\u0e35 1 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 35101 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e19\u0e04\u0e23\u0e2b\u0e25\u0e27\u0e07 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e01\u0e23\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e01\u0e23\u0e13\u0e35 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e23\u0e2a\u0e34\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e40\u0e2d \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124437\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124437 \u0e1a\u0e08.\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e44\u0e1f\u0e09\u0e32\u0e22 \u0e44\u0e1f\u0e09\u0e32\u0e22\u0e04\u0e32\u0e14\u0e2b\u0e31\u0e27 \u0e42\u0e04\u0e21\u0e44\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/80  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e38\u0e02\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c 8 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 26 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124445\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e2d\u0e35 2 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124445 \u0e1a\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e2d\u0e35 2 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 35101 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e19\u0e04\u0e23\u0e2b\u0e25\u0e27\u0e07 \u0e01\u0e32\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e15\u0e32\u0e21\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e01\u0e23\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e01\u0e23\u0e13\u0e35 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e23\u0e2a\u0e34\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e1a\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124453\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124453 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 43301 \u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15 (interior, furniture & metal works)\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e34\u0e25\u0e15\u0e4c\u0e2d\u0e34\u0e19 (built-in) \u0e07\u0e32\u0e19\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e25\u0e2d\u0e22\u0e15\u0e31\u0e27\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e40\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u5efa\u8a2d 523  \u0e0b\u0e2d\u0e22 \u0e19\u0e1e\u0e40\u0e01\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124470\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e08\u0e31\u0e19\u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124470 \u0e1a\u0e08.\u0e2d\u0e35\u0e08\u0e31\u0e19\u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u88fd\u9020 399\/119  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e1e\u0e23\u0e35\u0e21\u0e48\u0e32 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 50 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124500\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124500 \u0e1a\u0e08.\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2014\/7  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 43 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124518\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e44\u0e25\u0e19\u0e4c \u0e04\u0e2d\u0e21\u0e21\u0e2d\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10619\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10619\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124518 \u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e44\u0e25\u0e19\u0e4c \u0e04\u0e2d\u0e21\u0e21\u0e2d\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 10619 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e2a\u0e39\u0e15\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u88fd\u9020 57  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1b\u0e32\u0e23\u0e4c\u0e04\u0e40\u0e27\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e4c \u0e2d\u0e35\u0e42\u0e04\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124526\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e19\u0e32\u0e44\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124526 \u0e1a\u0e08.\u0e44\u0e2d\u0e19\u0e32\u0e44\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19 (supply chain) \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2\/1  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 20 \u0e41\u0e22\u0e01 2-1 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124534\",\"name_th\":\"\u0e1a\u0e08.4\u0e14\u0e35\u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124534 \u0e1a\u0e08.4\u0e14\u0e35\u0e1f\u0e39\u0e4a\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 12  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 47\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124542\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e17\u0e35\u0e1f \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124542 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e40\u0e08\u0e19\u0e40\u0e19\u0e2d\u0e40\u0e23\u0e17\u0e35\u0e1f \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/19  \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e19\u0e32\u0e19\u0e34\u0e04\u0e21 1 (\u0e21.\u0e40\u0e2a\u0e19\u0e32\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 1) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124551\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e17\u0e23\u0e34\u0e2d\u0e2d\u0e19 \u0e1f\u0e35\u0e14\u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124551 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e17\u0e23\u0e34\u0e2d\u0e2d\u0e19 \u0e1f\u0e35\u0e14\u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01,\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e22\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u88fd\u9020 3829  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e0b\u0e2d\u0e22 \u0e42\u0e22\u0e18\u0e34\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e3211\u0e41\u0e22\u0e017 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124593\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124593 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell\/solar rooftop) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (cctv) \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 150  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 89 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124607\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e27\u0e23\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124607 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e27\u0e23\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46109 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/124  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e25\u0e2d\u0e2a\u0e0b\u0e31\u0e48\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e2d\u0e17 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e2d\u0e31\u0e25\u0e17\u0e34\u0e17\u0e39\u0e14\u0e22\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124623\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e17\u0e22 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"50121\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"50121\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124623 \u0e1a\u0e08.\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e17\u0e22 \u0e2e\u0e2d\u0e44\u0e23\u0e0b\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 50121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 77\/149  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e2a\u0e32\u0e18\u0e23\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124674\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82920\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82920\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124674 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 82920 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e09\u0e25\u0e32\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 133\/4  \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e41\u0e01\u0e07\u0e32\u0e21 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124682\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e17\u0e42\u0e21\u0e2a \u0e41\u0e1e\u0e25\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28191\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28191\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124682 \u0e1a\u0e08.\u0e41\u0e2d\u0e17\u0e42\u0e21\u0e2a \u0e41\u0e1e\u0e25\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 28191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u88fd\u9020 15\/67  \u0e0b\u0e2d\u0e22 1 \u0e41\u0e22\u0e01 3-4 \u0e21.\u0e40\u0e0b\u0e19\u0e42\u0e17\u0e23 \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124712\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c\u0e44\u0e17\u0e25\u0e4c\u0e01\u0e23\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47511\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47511\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124712 \u0e1a\u0e08.\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c\u0e44\u0e17\u0e25\u0e4c\u0e01\u0e23\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47511 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 604  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 92\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124721\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e19\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124721 \u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e19\u0e40\u0e0b\u0e40\u0e27\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14  \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 5  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e1b\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e2d\u0e19 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021573\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e21\u0e32\u0e22\u0e40\u0e14\u0e22\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021573 \u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e21\u0e32\u0e22\u0e40\u0e14\u0e22\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 95\/165  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021590\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e4a\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021590 \u0e1a\u0e08.\u0e17\u0e4a\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e02\u0e31\u0e1a \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021603\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e14\u0e35\u0e44\u0e2d\u0e27\u0e32\u0e22 \u0e0b\u0e32\u0e27\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"26403\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"26403\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021603 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e14\u0e35\u0e44\u0e2d\u0e27\u0e32\u0e22 \u0e0b\u0e32\u0e27\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 26403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e25\u0e4d\u0e32\u0e42\u0e1e\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e15\u0e39\u0e49\u0e25\u0e4d\u0e32\u0e42\u0e1e\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e22\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u88fd\u9020 166\/174  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021611\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e14\u0e35.\u0e17\u0e35. 77 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021611 \u0e1a\u0e08.\u0e1e\u0e35.\u0e14\u0e35.\u0e17\u0e35. 77 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 94\/561  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021646\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e1b\u0e23\u0e14 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021646 \u0e1a\u0e08.\u0e21\u0e32\u0e42\u0e1b\u0e23\u0e14 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46311 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e01\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e38\u0e01\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e38\u0e01\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021654\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e34\u0e04\u0e19\u0e34\u0e04\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021654 \u0e1a\u0e08.\u0e1b\u0e34\u0e04\u0e19\u0e34\u0e04\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 25119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a \u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c  \u0e42\u0e04\u0e23\u0e07\u0e1b\u0e34\u0e04\u0e19\u0e34\u0e04 \u0e25\u0e49\u0e2d\u0e27\u0e32\u0e07\u0e16\u0e31\u0e07\u0e41\u0e01\u0e4a\u0e2a \u0e17\u0e35\u0e48\u0e1a\u0e31\u0e07\u0e25\u0e21\u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a \u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e16\u0e31\u0e07\u0e41\u0e01\u0e4a\u0e2a\u0e1b\u0e34\u0e04\u0e19\u0e34\u0e04 \u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e40\u0e15\u0e32\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e01\u0e25\u0e21\u0e2a\u0e39\u0e07 \u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e40\u0e15\u0e32\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e15\u0e31\u0e49\u0e07\u0e40\u0e15\u0e32\u0e41\u0e21\u0e48\u0e04\u0e49\u0e32 \u0e17\u0e38\u0e01\u0e41\u0e1a\u0e1a \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 1\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021662\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d.\u0e14\u0e35.\u0e40\u0e2d\u0e2a. \u0e42\u0e1f\u0e25\u0e4c\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c \u0e40\u0e0b\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021662 \u0e1a\u0e08.\u0e40\u0e2d.\u0e14\u0e35.\u0e40\u0e2d\u0e2a. \u0e42\u0e1f\u0e25\u0e4c\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c \u0e40\u0e0b\u0e25\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e16\u0e42\u0e1f\u0e25\u0e4c\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e42\u0e1f\u0e25\u0e4c\u0e04\u0e25\u0e34\u0e1f\u0e17\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 999\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021671\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e2d\u0e35\u0e2d\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021671 \u0e1a\u0e08.\u0e0b\u0e35\u0e2d\u0e35\u0e2d\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 (holding company) \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e25\u0e07\u0e17\u0e38\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 145  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021697\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021697 \u0e1a\u0e08.\u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 999\/171  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021727\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e0b\u0e35.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27. \u0e25\u0e2d\u0e27\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021727 \u0e1a\u0e08.\u0e1e\u0e35.\u0e0b\u0e35.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27. \u0e25\u0e2d\u0e27\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 750\/151  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024416\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e21\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024416 \u0e1a\u0e08.\u0e19\u0e31\u0e21\u0e40\u0e27\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 58202 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c: \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 (licensing) \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c (cloud computing) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 123\/66  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e19\u0e19\u0e17\u0e4c 12 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024424\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e1f\u0e34\u0e19 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e40\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024424 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e1f\u0e34\u0e19 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e40\u0e01\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 93  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 6 \u0e41\u0e22\u0e01 19 \u0e16\u0e19\u0e19\u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024432\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024432 \u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e42\u0e14\u0e22\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e1f\u0e23\u0e19\u0e0a\u0e32\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e0a\u0e32\u0e23\u0e4c\u0e15\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 89\/56  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e18\u0e19\u0e32\u0e27\u0e34\u0e25\u0e40\u0e25\u0e082 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e215-\u0e1a\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 \u0e42\u0e22\u0e18\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23 \u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 2032 (\u0e41\u0e01\u0e49\u0e27\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c) \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024459\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e1e \u0e17\u0e39 \u0e22\u0e39 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024459 \u0e1a\u0e08.\u0e2d\u0e31\u0e1e \u0e17\u0e39 \u0e22\u0e39 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 36\/126  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e27\u0e07\u0e28\u0e4c\u0e2a\u0e27\u0e48\u0e32\u0e07-\u0e41\u0e04\u0e23\u0e32\u0e22 \u0e16\u0e19\u0e19\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024505\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e2d\u0e23\u0e48\u0e32 \u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024505 \u0e1a\u0e08.\u0e2d\u0e04\u0e27\u0e2d\u0e23\u0e48\u0e32 \u0e04\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 58202 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a saas \/ cloud \/ \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 99\/175  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e31\u0e14\u0e14\u0e32\u0e23\u0e21\u0e22\u0e4c \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c 2 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024513\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e38\u0e25\u0e08\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024513 \u0e1a\u0e08.\u0e01\u0e38\u0e25\u0e08\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 168\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024521\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34 \u0e40\u0e2d\u0e40\u0e1b\u0e01\u0e0b\u0e4c \u0e0b\u0e35\u0e17\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95110\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95110\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024521 \u0e1a\u0e08.\u0e14\u0e34 \u0e40\u0e2d\u0e40\u0e1b\u0e01\u0e0b\u0e4c \u0e0b\u0e35\u0e17\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 95110 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 it \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 108\/170  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024564\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e23\u0e34\u0e19\u0e15\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024564 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e23\u0e34\u0e19\u0e15\u0e4c \u0e2d\u0e34\u0e19\u0e17\u0e34\u0e40\u0e01\u0e23\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e48\u0e40\u0e0a\u0e48\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 189\/60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024572\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e39\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024572 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e39\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e27\u0e34\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 43\/1  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e2d\u0e34\u0e10 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024599\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e0b \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024599 \u0e1a\u0e08.\u0e04\u0e34\u0e0b \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17  \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 76\/58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024611\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e22\u0e32 \u0e23\u0e34\u0e0a \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024611 \u0e1a\u0e08.\u0e1b\u0e23\u0e35\u0e22\u0e32 \u0e23\u0e34\u0e0a \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e0a\u0e48\u0e32 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e15\u0e48\u0e2d \u0e15\u0e01\u0e40\u0e40\u0e15\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e40\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e40\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e40\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u4e0d\u52d5\u7523 222\/308  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024629\",\"name_th\":\"\u0e1a\u0e08.3\u0e40\u0e2d\u0e2a \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024629 \u0e1a\u0e08.3\u0e40\u0e2d\u0e2a \u0e41\u0e25\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u4e0d\u52d5\u7523 35\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024637\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e1a\u0e35 \u0e40\u0e21\u0e0b\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024637 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e1a\u0e35 \u0e40\u0e21\u0e0b\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u4e0d\u52d5\u7523 2  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c 22 \u0e41\u0e22\u0e01 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024645\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e04\u0e23\u0e31\u0e27\u0e43\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024645 \u0e1a\u0e08.\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e04\u0e23\u0e31\u0e27\u0e43\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 95\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024653\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e15\u0e2d\u0e21.\u0e17\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024653 \u0e1a\u0e08.\u0e2d\u0e30\u0e15\u0e2d\u0e21.\u0e17\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 shopee lazada tiktok \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/79  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 pleno \u0e1a\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e2f \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024670\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e04\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024670 \u0e1a\u0e08.\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e04\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 40\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024688\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35. \u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e34\u0e40\u0e01\u0e34\u0e49\u0e25 \u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024688 \u0e1a\u0e08.\u0e1a\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35. \u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e34\u0e40\u0e01\u0e34\u0e49\u0e25 \u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e44\u0e21\u0e49\u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e34\u0e40\u0e01\u0e34\u0e25\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e44\u0e21\u0e49\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35\u0e40\u0e2d\u0e1f\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024696\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e42\u0e25\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024696 \u0e1a\u0e08.\u0e40\u0e0b\u0e42\u0e25\u0e23\u0e34\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46441 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/319  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e44\u0e04\u0e15\u0e31\u0e04  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 k005040 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1b\u0e4a\u0e2d\u0e1a\u0e1b\u0e39\u0e25\u0e48\u0e32 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020160\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e35 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020160 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e35 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020178\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e44\u0e25\u0e17\u0e4c 4691 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020178 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e14\u0e32\u0e44\u0e25\u0e17\u0e4c 4691 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 135\/159  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 13 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020224\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e1f\u0e34\u0e01\u0e0b\u0e4c \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25922\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25922\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020224 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e1f\u0e34\u0e01\u0e0b\u0e4c \u0e1e\u0e23\u0e35\u0e0b\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 25922 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e01\u0e25\u0e36\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e08\u0e35\u0e22\u0e23\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 79\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020232\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10795\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10795\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020232 \u0e1a\u0e08.\u0e40\u0e22\u0e47\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 10795 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22 \u0e19\u0e49\u0e33 \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 65\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020241\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e32 \u0e0b\u0e35\u0e1f\u0e39\u0e4a\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10291\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10291\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020241 \u0e1a\u0e08.\u0e23\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e32 \u0e0b\u0e35\u0e1f\u0e39\u0e4a\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 10291 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u88fd\u9020 65\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020259\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e1f\u0e19\u0e0b\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020259 \u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e1f\u0e19\u0e0b\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e17\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 71\/259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020291\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e39 \u0e2a\u0e38\u0e27\u0e34\u0e20\u0e1e \u0e40\u0e0b\u0e17\u0e2d\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020291 \u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e39 \u0e2a\u0e38\u0e27\u0e34\u0e20\u0e1e \u0e40\u0e0b\u0e17\u0e2d\u0e31\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e39\u0e17\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 40\/252  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020305\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e0b\u0e27\u0e31\u0e19 \u0e17\u0e32\u0e40\u0e25\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020305 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e0b\u0e27\u0e31\u0e19 \u0e17\u0e32\u0e40\u0e25\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 22\/40  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 89 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020321\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08\u0e27\u0e34\u0e04\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e27\u0e35 16 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020321 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08\u0e27\u0e34\u0e04\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e27\u0e35 16 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 38\/164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020330\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27 \u0e40\u0e1f\u0e23\u0e21 \u0e42\u0e2e\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020330 \u0e1a\u0e08.\u0e04\u0e34\u0e27 \u0e40\u0e1f\u0e23\u0e21 \u0e42\u0e2e\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 50\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 46\/1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020348\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020348 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e19\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e15\u0e4d\u0e48\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30\u0e19\u0e49\u0e33\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 44\/223  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e17\u0e32\u0e22 \u0e40\u0e1e\u0e25\u0e2a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020356\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e42\u0e23\u0e2a\u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020356 \u0e1a\u0e08.\u0e1f\u0e35\u0e42\u0e23\u0e2a\u0e2e\u0e32\u0e25\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020381\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e19\u0e34\u0e17\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020381 \u0e1a\u0e08.\u0e0b\u0e35\u0e19\u0e34\u0e17\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 45302 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/32  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e22\u0e39\u0e19\u0e34\u0e42\u0e2d \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32\u0e04\u0e25\u0e2d\u0e074 \u0e16\u0e19\u0e19\u0e44\u0e2a\u0e27\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020399\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e2d\u0e19 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020399 \u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e2d\u0e19 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e08\u0e32\u0e23\u0e1a\u0e35 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 295  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 85 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020402\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"13132\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"13132\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020402 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 13132 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e32\u0e22 \u0e2a\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 16\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020411\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e39\u0e19\u0e2a\u0e38\u0e02 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47221\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47221\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020411 \u0e1a\u0e08.\u0e1e\u0e39\u0e19\u0e2a\u0e38\u0e02 \u0e15\u0e31\u0e49\u0e07\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35\/98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020429\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e15\u0e40\u0e14\u0e49\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020429 \u0e1a\u0e08.\u0e21\u0e35\u0e15\u0e40\u0e14\u0e49\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 88\/38  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e38\u0e0d\u0e22\u0e01\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020453\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e0b\u0e35\u0e2a\u0e40\u0e17\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020453 \u0e1a\u0e08.\u0e14\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e0b\u0e35\u0e2a\u0e40\u0e17\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 18\/194  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020461\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020461 \u0e1a\u0e08.\u0e14\u0e32\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 65\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020470\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35\u0e1a\u0e35 \u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020470 \u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35\u0e1a\u0e35 \u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 32909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u88fd\u9020 61\/147  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020488\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e48\u0e27\u0e22 \u0e40\u0e19\u0e34\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87301\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87301\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020488 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e48\u0e27\u0e22 \u0e40\u0e19\u0e34\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 87301 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u533b\u7642\u30fb\u798f\u7949 36\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004369\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e21\u0e0a\u0e19\u0e0156 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004369 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e21\u0e0a\u0e19\u0e0156 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1b\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32 \u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0145569004377\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e48\u0e1a \u0e2a\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e22\u0e42\u0e04\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004377 \u0e1a\u0e08.\u0e41\u0e0b\u0e48\u0e1a \u0e2a\u0e27\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e22\u0e42\u0e04\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0163569000523\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e0a\u0e32\u0e22 \u0e2d\u0e25\u0e39\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000523 \u0e2b\u0e08.\u0e2a\u0e21\u0e0a\u0e32\u0e22 \u0e2d\u0e25\u0e39\u0e21\u0e32\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e41\u0e25\u0e30\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5efa\u8a2d 5\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001467\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19\u0e0b\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001467 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19\u0e0b\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0165569001475\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001475 \u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e41\u0e1e\u0e23\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e48\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (live streaming) \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 tiktok \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 92\/54  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e07\u0e27\u0e32\u0e25\u0e22\u0e4c \u0e41\u0e22\u0e01 4 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000698\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e27\u0e35.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000698 \u0e2b\u0e08.\u0e27\u0e35.\u0e2d\u0e32\u0e23\u0e4c.\u0e27\u0e35.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-01 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2a\u0e32\u0e22\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u5efa\u8a2d 120  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002711\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e22\u0e41\u0e2d\u0e25 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002711 \u0e2b\u0e08.\u0e27\u0e32\u0e22\u0e41\u0e2d\u0e25 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 2569-07-01 1000000 46414 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002720\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e08 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0203569002720 \u0e2b\u0e08.\u0e40\u0e2d\u0e40\u0e08 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 2569-07-01 1000000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 239\/841  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569034542\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e01\u0e23\u0e34\u0e40\u0e17\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034542 \u0e1a\u0e08.\u0e2d\u0e30\u0e01\u0e23\u0e34\u0e40\u0e17\u0e04 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e38\u0e4b\u0e22 \u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/395  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034551\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e34\u0e01\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e2d\u0e42\u0e01\u0e23\u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034551 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e34\u0e01\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e2d\u0e42\u0e01\u0e23\u0e40\u0e04\u0e21\u0e35\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e37\u0e0a \u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e01\u0e33\u0e08\u0e31\u0e14\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 133\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034569\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e1b\u0e1b\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034569 \u0e1a\u0e08.\u0e2d\u0e31\u0e1b\u0e1b\u0e2d\u0e23\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e33 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e02\u0e38\u0e14 \u0e23\u0e16\u0e1a\u0e14 \u0e23\u0e16\u0e22\u0e01\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 149\/133  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034585\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034585 \u0e1a\u0e08.\u0e0b\u0e35\u0e1e\u0e35 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47630 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e20\u0e32\u0e04\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e17\u0e38\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 190\/266  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034615\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f\u0e2d\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034615 \u0e1a\u0e08.\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f\u0e2d\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 368\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034674\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e04\u0e48\u0e30 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034674 \u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e04\u0e48\u0e30 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01 \u0e2d\u0e1a \u0e23\u0e35\u0e14 \u0e1c\u0e49\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 3\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034682\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e2d\u0e07 \u0e1e\u0e35.\u0e40\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034682 \u0e1a\u0e08.\u0e01\u0e49\u0e2d\u0e07 \u0e1e\u0e35.\u0e40\u0e04. \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u88fd\u9020 3\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034721\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e39 \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034721 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e39 \u0e40\u0e21\u0e17\u0e31\u0e25 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e42\u0e25\u0e2b\u0e30\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e15\u0e31\u0e14 \u0e1e\u0e31\u0e1a \u0e21\u0e49\u0e27\u0e19 \u0e0a\u0e38\u0e1a \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e36\u0e07\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e01\u0e25\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 36\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034755\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e13\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034755 \u0e1a\u0e08.\u0e21\u0e13\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e32\u0e21\u0e25\u0e49\u0e2d\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e16\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 126\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034763\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e40\u0e1a\u0e25 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034763 \u0e1a\u0e08.\u0e1a\u0e32\u0e40\u0e1a\u0e25 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c           \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e25\u0e31\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 9\/51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034780\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e22\u0e39 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034780 \u0e1a\u0e08.\u0e40\u0e04\u0e22\u0e39 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 29\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034798\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19 \u0e44\u0e23\u0e0b\u0e4c 98 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034798 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e21\u0e31\u0e19 \u0e44\u0e23\u0e0b\u0e4c 98 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e16\u0e38\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46  \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/71  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e27\u0e35\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c 41 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034801\",\"name_th\":\"\u0e1a\u0e08. \u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e41\u0e21\u0e48 \u0e43\u0e2b\u0e49\u0e21\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034801 \u0e1a\u0e08. \u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e41\u0e21\u0e48 \u0e43\u0e2b\u0e49\u0e21\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e15\u0e32\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07 \u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30 \u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034828\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e2d \u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034828 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e2d \u0e41\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u5efa\u8a2d 209\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034852\",\"name_th\":\"\u0e1a\u0e08.\u0e2a.\u0e2a\u0e38\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e41\u0e17\u0e23\u0e1f\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034852 \u0e1a\u0e08.\u0e2a.\u0e2a\u0e38\u0e18\u0e34\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e41\u0e17\u0e23\u0e1f\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 54\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034895\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034895 \u0e1a\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e27\u0e32\u0e07\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e2a\u0e48\u0e07\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23  \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 17\/171  \u0e0b\u0e2d\u0e22 \u0e42\u0e1b\u0e29\u0e22\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034909\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e01\u0e31\u0e19\u0e2b\u0e32\u0e0a\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034909 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e01\u0e31\u0e19\u0e2b\u0e32\u0e0a\u0e31\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (cctv) \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e35\u0e42\u0e21\u0e17\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e32\u0e19\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21  \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 99\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001146\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e31\u0e25\u0e40\u0e25\u0e22\u0e4c \u0e40\u0e2d\u0e08\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001146 \u0e2b\u0e08.\u0e27\u0e31\u0e25\u0e40\u0e25\u0e22\u0e4c \u0e40\u0e2d\u0e08 2569-07-01 1000000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 256\/96  \u0e16\u0e19\u0e19\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008762\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008762 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e04\u0e48\u0e32\u0e41\u0e23\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 209\/29  \u0e16\u0e19\u0e19\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e22\u0e2d\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008797\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008797 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e23\u0e30\u0e22\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d \u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 574\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569008835\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e20\u0e32\u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77309\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77309\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008835 \u0e1a\u0e08.\u0e27\u0e34\u0e20\u0e32\u0e40\u0e04\u0e23\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 77309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e01\u0e23\u0e30\u0e40\u0e0a\u0e49\u0e32 \u0e23\u0e16\u0e40\u0e2e\u0e35\u0e4a\u0e22\u0e1a \u0e40\u0e17\u0e1b\u0e39 \u0e23\u0e16\u0e22\u0e01 \u0e22\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e22\u0e01\u0e42\u0e04\u0e23\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 639\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0223569000301\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e47\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10795\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10795\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0223569000301 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e47\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-01 1000000 10795 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 6\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003515\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e13 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003515 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e13 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e2e\u0e19\u0e14\u0e4c\u0e40\u0e21\u0e14 \u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 793  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003523\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63990\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63990\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003523 \u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 63990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e41\u0e04\u0e2a\u0e15\u0e4c\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e15\u0e32\u0e21\u0e01\u0e0e \u60c5\u5831\u901a\u4fe1\u30fbit 244\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0265569000745\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000745 \u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e31\u0e1a \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e15\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0265569000753\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e0a\u0e22\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000753 \u0e1a\u0e08.\u0e1e\u0e35\u0e23\u0e0a\u0e22\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e04\u0e21\u0e1b\u0e4c\u0e1b\u0e34\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u5bbf\u6cca\u30fb\u98f2\u98df 390  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0273569000450\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e20\u0e32888\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0273569000450 \u0e2b\u0e08.\u0e2a\u0e38\u0e20\u0e32888 2569-07-01 1000000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c ( \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 ) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0275569001091\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001091 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002524\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e49\u0e19\u0e08\u0e4c \u0e2a\u0e01\u0e32\u0e22 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002524 \u0e2b\u0e08.\u0e2d\u0e2d\u0e40\u0e23\u0e49\u0e19\u0e08\u0e4c \u0e2a\u0e01\u0e32\u0e22 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c 2569-07-01 1000000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 151\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002532\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e30 628 \u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002532 \u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e30 628 \u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-01 1000000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30\u0e1a\u0e48\u0e2d\u0e19\u0e4d\u0e49\u0e32\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e02\u0e38\u0e14\u0e2a\u0e23\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e19\u0e4d\u0e49\u0e32 \u0e02\u0e38\u0e14\u0e1a\u0e48\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e4d\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e48\u0e2d\u0e1a\u0e4d\u0e32\u0e1a\u0e31\u0e14\u0e19\u0e4d\u0e49\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e07\u0e32\u0e19\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01\u0e04\u0e39\u0e04\u0e25\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e16\u0e21\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e14\u0e34\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 329  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0303569002541\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e23\u0e38\u0e08\u0e19\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002541 \u0e2b\u0e08.\u0e19\u0e34\u0e18\u0e34\u0e23\u0e38\u0e08\u0e19\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-01 1000000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006840\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d.\u0e2d\u0e32\u0e23\u0e4c. \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006840 \u0e1a\u0e08.\u0e40\u0e2d.\u0e2d\u0e32\u0e23\u0e4c. \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e04\u0e2d\u0e25\u0e25\u0e32\u0e40\u0e08\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 555\/154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006858\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e0d\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006858 \u0e1a\u0e08.\u0e0a\u0e0d\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 217,219,221,223  \u0e16\u0e19\u0e19\u0e08\u0e2d\u0e21\u0e1e\u0e25 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569006866\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e42\u0e18\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006866 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e42\u0e18\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e22\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e19 \u533b\u7642\u30fb\u798f\u7949 1089\/1  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e19\u0e32\u0e23\u0e32\u0e22\u0e13\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001805\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e2a \u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001805 \u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e2a \u0e1e\u0e35\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0325569001139\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1e\u0e35\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001139 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e1e\u0e35\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0333569000629\",\"name_th\":\"\u0e2b\u0e08.\u0e10\u0e32\u0e01\u0e39\u0e23\u0e28\u0e34\u0e23\u0e34\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000629 \u0e2b\u0e08.\u0e10\u0e32\u0e01\u0e39\u0e23\u0e28\u0e34\u0e23\u0e34 2569-07-01 1000000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e44\u0e16\u0e19\u0e32 \u0e23\u0e16\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e32\u0e27 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0335569001082\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c. \u0e27\u0e34\u0e19\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001082 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e2d\u0e32\u0e23\u0e4c. \u0e27\u0e34\u0e19\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0343569001781\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2a\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001781 \u0e2b\u0e08.\u0e41\u0e2a\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 2569-07-01 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 365  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0343569001790\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001790 \u0e2b\u0e08.\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 2569-07-01 1000000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 275  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0363569000823\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e32\u0e29\u0e35\u0e2a\u0e27\u0e22 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000823 \u0e2b\u0e08.\u0e23\u0e32\u0e29\u0e35\u0e2a\u0e27\u0e22 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-01 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e14\u0e34\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e07\u0e32\u0e19\u0e02\u0e38\u0e14 \u0e16\u0e21 \u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d \u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e02\u0e38\u0e14\u0e04\u0e39 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2b\u0e34\u0e19 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e2b\u0e34\u0e19 \u0e2f\u0e25\u0e2f \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e16\u0e19\u0e19\u0e41\u0e25\u0e30\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e23\u0e31\u0e49\u0e27 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e49\u0e27\u0e16\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u5efa\u8a2d 75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0373569000220\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e19\u0e19\u0e17\u0e4c\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0373569000220 \u0e2b\u0e08.\u0e2d\u0e32\u0e19\u0e19\u0e17\u0e4c\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-01 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 98  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0383569000254\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e38\u0e20\u0e0a\u0e31\u0e22\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e17\u0e48\u0e32\u0e2a\u0e30\u0e2d\u0e32\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0383569000254 \u0e2b\u0e08.\u0e28\u0e38\u0e20\u0e0a\u0e31\u0e22\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e17\u0e48\u0e32\u0e2a\u0e30\u0e2d\u0e32\u0e14 2569-07-01 1000000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a-\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e25\u0e49\u0e2d\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e19\u0e15\u0e4c \u0e02\u0e2d\u0e07 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 251  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0385569000469\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e25\u0e2d\u0e07 \u0e40\u0e01\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000469 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e25\u0e2d\u0e07 \u0e40\u0e01\u0e21 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e27\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33  (leadership development) \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 20 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0395569000400\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e27\u0e34\u0e19\u0e34\u0e15\u0e22\u0e4c \u0e2a\u0e38\u0e27\u0e34\u0e0a\u0e32 \u0e1c\u0e25\u0e14\u0e35 \u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000400 \u0e1a\u0e08.\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e27\u0e34\u0e19\u0e34\u0e15\u0e22\u0e4c \u0e2a\u0e38\u0e27\u0e34\u0e0a\u0e32 \u0e1c\u0e25\u0e14\u0e35 \u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e2b\u0e19\u0e35\u0e49\u0e2a\u0e34\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e19\u0e35\u0e49 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e2d\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e35\u0e49 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e35\u0e49\u0e17\u0e31\u0e49\u0e07\u0e21\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e35\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 388\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0403569002876\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002876 \u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e0a\u0e31\u0e48\u0e19 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 9\/212  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1a\u0e2a\u0e42\u0e2e\u0e21\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569002892\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e15\u0e32\u0e25\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002892 \u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e15\u0e32\u0e25\u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 2569-07-01 1000000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e49\u0e32\u0e22\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e44\u0e1f\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e44\u0e1f\u0e2a\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e08\u0e23\u0e32\u0e08\u0e23\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e1a\u0e17\u0e32\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e07\u0e32\u0e19\u0e08\u0e23\u0e32\u0e08\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e15\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e08\u0e23\u0e32\u0e08\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46\u0e27\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e32\u0e07\u0e08\u0e23\u0e32\u0e08\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 175  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006253\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006253 \u0e1a\u0e08.\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68101 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 418  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006261\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e27\u0e39\u0e4a\u0e14\u0e0a\u0e34\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006261 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35 \u0e27\u0e39\u0e4a\u0e14\u0e0a\u0e34\u0e1e \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46632 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e44\u0e21\u0e49\u0e2a\u0e31\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e44\u0e21\u0e49\u0e2a\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e0a\u0e32\u0e19\u0e2d\u0e49\u0e2d\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 653  \u0e16\u0e19\u0e19\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006270\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006270 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003378\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e21\u0e32\u0e17\u0e35\u0e18\u0e41\u0e25\u0e30\u0e40\u0e14\u0e2d\u0e21\u0e32\u0e1a\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003378 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e21\u0e32\u0e17\u0e35\u0e18\u0e41\u0e25\u0e30\u0e40\u0e14\u0e2d\u0e21\u0e32\u0e1a\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e35\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e35\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e04\u0e25\u0e35\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e15\u0e32\u0e21\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u533b\u7642\u30fb\u798f\u7949 74\/3-4  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003408\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003408 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e08 \u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e48\u0e32\u0e08\u0e32\u0e19 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0445569001570\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e2d\u0e34\u0e1a\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18122\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18122\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001570 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e2d\u0e34\u0e1a\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 18122 \u0e1b\u0e23\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e1a\u0e1a\u0e41\u0e1b\u0e25\u0e19 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e25\u0e48\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e46 \u88fd\u9020 146  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0463569000679\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e19\u0e31\u0e01 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000679 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e19\u0e31\u0e01 \u0e01\u0e23\u0e30\u0e08\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 2569-07-01 1000000 23101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e23\u0e30\u0e08\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e1d\u0e49\u0e32 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e21\u0e38\u0e49\u0e07\u0e25\u0e27\u0e14 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e21\u0e49\u0e27\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u88fd\u9020 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0465569000816\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e04.\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000816 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e04.\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e2d\u0e31\u0e19\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e49\u0e27\u0e22 \u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/5-14  \u0e16\u0e19\u0e19\u0e16\u0e35\u0e19\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0475569001367\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c 2023 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001367 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e08 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c 2023 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c  \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e2a\u0e48\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e2a\u0e48\u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e2a\u0e48\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 798\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0475569001375\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e2a\u0e32\u0e23 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001375 \u0e1a\u0e08.\u0e18\u0e19\u0e2a\u0e32\u0e23 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 239  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000859\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e1a\u0e19\u0e31\u0e27\u0e04\u0e23\u0e31\u0e27\u0e42\u0e02\u0e07 \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000859 \u0e1a\u0e08.\u0e41\u0e0b\u0e1a\u0e19\u0e31\u0e27\u0e04\u0e23\u0e31\u0e27\u0e42\u0e02\u0e07 \u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 177\/3  \u0e16\u0e19\u0e19\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0495569000492\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e1e\u0e35258\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000492 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e04\u0e1e\u0e35258\u0e40\u0e2e\u0e34\u0e23\u0e4c\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 146  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004274\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e38\u0e42\u0e1a\u0e2a\u0e16\u0e27\u0e32\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004274 \u0e2b\u0e08.\u0e2d\u0e38\u0e42\u0e1a\u0e2a\u0e16\u0e27\u0e32\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-01 1000000 46692 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 501  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e42\u0e1a\u0e2a\u0e16 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004291\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004291 \u0e2b\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c 2569-07-01 1000000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2a\u0e1a\u0e39\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 34  \u0e16\u0e19\u0e19\u0e27\u0e31\u0e27\u0e25\u0e32\u0e22 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014735\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014735 \u0e1a\u0e08.\u0e2e\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e02\u0e35\u0e48\u0e21\u0e49\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e21\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e35\u0e48\u0e21\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e21\u0e49\u0e32 \u6559\u80b2 119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014751\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e42\u0e23\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014751 \u0e1a\u0e08.\u0e19\u0e34\u0e27\u0e42\u0e23\u0e0b\u0e35\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e27\u0e07\u0e08\u0e23\u0e23\u0e27\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 132  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014760\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e2d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014760 \u0e1a\u0e08.\u0e04\u0e35\u0e2d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u4e0d\u52d5\u7523 125\/12  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e27\u0e35\u0e22\u0e07\u0e19\u0e49\u0e33\u0e25\u0e49\u0e2d\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014778\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e04\u0e15\u0e15\u0e35\u0e49 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014778 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e04\u0e15\u0e15\u0e35\u0e49 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 299\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014816\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e17\u0e35 \u0e40\u0e2d\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64991\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64991\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014816 \u0e1a\u0e08.\u0e40\u0e2d \u0e17\u0e35 \u0e40\u0e2d\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 64991 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e19\u0e35\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e23\u0e35\u0e22\u0e01\u0e23\u0e49\u0e2d\u0e07\u0e2b\u0e19\u0e35\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e49\u0e2d\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u91d1\u878d\u30fb\u4fdd\u967a 486\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014832\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e1b\u0e10\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20210\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20210\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014832 \u0e1a\u0e08.\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e1b\u0e10\u0e1e\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 20210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e2a\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15 \u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c\u0e27\u0e31\u0e15\u0e16\u0e38 \u0e08\u0e38\u0e25\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e21\u0e35 \u88fd\u9020 103\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014841\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e18\u0e19\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014841 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e18\u0e19\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 51\/94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014859\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e25\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e25 \u0e42\u0e23\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014859 \u0e1a\u0e08.\u0e2d\u0e25\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e25 \u0e42\u0e23\u0e2a\u0e40\u0e17\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014867\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e35 \u0e40\u0e17\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014867 \u0e1a\u0e08.\u0e22\u0e39 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e35 \u0e40\u0e17\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e2a\u0e39\u0e17 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 73\/25  \u0e16\u0e19\u0e19\u0e40\u0e27\u0e35\u0e22\u0e07\u0e1e\u0e34\u0e07\u0e04\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014875\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014875 \u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e17\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e17\u0e35\u0e27\u0e35 \u0e08\u0e32\u0e19\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e41\u0e2d\u0e23\u0e4c \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 150\/107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014883\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e42\u0e15 \u0e40\u0e14\u0e2d \u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014883 \u0e1a\u0e08.\u0e0a\u0e32\u0e23\u0e4c\u0e42\u0e15 \u0e40\u0e14\u0e2d \u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000651\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e42\u0e01\u0e23\u0e27\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000651 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e42\u0e01\u0e23\u0e27\u0e4c 2569-07-01 1000000 73101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 134  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0513569000660\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e42\u0e21 \u0e1a\u0e34\u0e25\u0e14\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000660 \u0e2b\u0e08.\u0e1f\u0e2d\u0e23\u0e4c\u0e42\u0e21 \u0e1a\u0e34\u0e25\u0e14\u0e4c 2569-07-01 1000000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 169  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0515569001340\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001340 \u0e1a\u0e08.\u0e22\u0e39\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 (hvac) \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 226\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001510\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e0a\u0e47\u0e2d\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001510 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e0a\u0e47\u0e2d\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e19\u0e49\u0e33\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e41\u0e25\u0e30\u0e02\u0e19\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 13\/827  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0545569000742\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000742 \u0e1a\u0e08.\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e1e\u0e35 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e23\u0e39\u0e1b\u0e23\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e1a\u0e1a \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08 \u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e0a\u0e30\u0e25\u0e2d\u0e27\u0e31\u0e22 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e02\u0e49\u0e2d\u0e1a\u0e01\u0e1e\u0e23\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u533b\u7642\u30fb\u798f\u7949 166\/44  \u0e16\u0e19\u0e19\u0e22\u0e31\u0e19\u0e15\u0e23\u0e01\u0e34\u0e08\u0e42\u0e01\u0e28\u0e25 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0555569000564\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000564 \u0e1a\u0e08.\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e23\u0e32 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569001976\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e35\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569001976 \u0e2b\u0e08.\u0e18\u0e35\u0e23\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 509\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004241\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004241 \u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e20\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 329  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004250\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e2a\u0e40\u0e1b\u0e0b \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004250 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e2a\u0e40\u0e1b\u0e0b \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0575569004276\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004276 \u0e1a\u0e08.\u0e1e\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e0a\u0e32 \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e2a\u0e32\u0e23\u0e01\u0e32\u0e41\u0e1f\u0e41\u0e25\u0e30\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e1a \u0e04\u0e31\u0e48\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569001870\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e2a\u0e4c\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001870 \u0e1a\u0e08.\u0e04\u0e2d\u0e19\u0e2a\u0e4c\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 789\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569001888\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001888 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46695 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0623569000677\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e14\u0e35\u0e2d\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000677 \u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e14\u0e35\u0e2d\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-01 1000000 32909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e07\u0e32\u0e19\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01  \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07  \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0635569001357\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e17\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001357 \u0e1a\u0e08.\u0e1a\u0e35\u0e17\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e2d\u0e34\u0e21\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3\/60  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0643569000481\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e34\u0e23\u0e20\u0e31\u0e17\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0643569000481 \u0e2b\u0e08.\u0e08\u0e34\u0e23\u0e20\u0e31\u0e17\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-01 1000000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23 \u8fb2\u6797\u6c34\u7523 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0645569000687\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35-\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000687 \u0e1a\u0e08.\u0e14\u0e35-\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e19\u0e31\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u5efa\u8a2d 217\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0645569000695\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e32 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42201\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42201\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000695 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e32 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 42201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e48\u0e2d\u0e40\u0e21\u0e19\u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e22\u0e48\u0e2d\u0e22 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 (\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e19\u0e49\u0e33) \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\/\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e0f\u0e34\u0e01\u0e39\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e20\u0e32\u0e0a\u0e19\u0e30 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e4d\u0e32\u0e08\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e42\u0e23\u0e07\u0e1a\u0e4d\u0e32\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e01\u0e32\u0e23\u0e02\u0e38\u0e14\u0e1a\u0e48\u0e2d\u0e19\u0e49\u0e33 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e48\u0e2d\u0e40\u0e01\u0e23\u0e2d\u0e30 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u5efa\u8a2d 1\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0655569002043\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002043 \u0e1a\u0e08.\u0e1e\u0e35\u0e14\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222\/58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002060\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e4a\u0e01 \u0e44\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002060 \u0e1a\u0e08.\u0e01\u0e34\u0e4a\u0e01 \u0e44\u0e01\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e19\u0e31\u0e01\u0e14\u0e19\u0e15\u0e23\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19\u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e34\u0e1b\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 202\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 2 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0705569003014\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003014 \u0e1a\u0e08.\u0e2d\u0e2d\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e01\u0e48\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 117\/64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003022\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e42\u0e04\u0e42\u0e04\u0e49 \u0e40\u0e04\u0e14\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003022 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e42\u0e04\u0e42\u0e04\u0e49 \u0e40\u0e04\u0e14\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e15\u0e23 \u0e1c\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002425\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e21\u0e48\u0e2d\u0e19 \u0e17\u0e23\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002425 \u0e1a\u0e08.\u0e40\u0e25\u0e21\u0e48\u0e2d\u0e19 \u0e17\u0e23\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 55101 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\/\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 91\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569000951\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e14\u0e23\u0e1f\u0e4c \u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e04\u0e32\u0e23\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569000951 \u0e2b\u0e08.\u0e44\u0e14\u0e23\u0e1f\u0e4c \u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e04\u0e32\u0e23\u0e4c 2569-07-01 1000000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e32\u0e22\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 168\/110  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006609\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e17\u0e21\u0e21\u0e32\u0e23\u0e34\u0e19\u0e14\u0e4c \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10619\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10619\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006609 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e41\u0e17\u0e21\u0e21\u0e32\u0e23\u0e34\u0e19\u0e14\u0e4c \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 10619 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e21\u0e30\u0e02\u0e32\u0e21 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e21\u0e30\u0e02\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e21\u0e30\u0e02\u0e32\u0e21 \u88fd\u9020 62\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006617\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006617 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e21\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006625\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e17\u0e31\u0e28\u0e19\u0e4c99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006625 \u0e1a\u0e08.\u0e2a\u0e38\u0e17\u0e31\u0e28\u0e19\u0e4c99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49339 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (logistics) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 53\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e07\u0e1e\u0e25\u0e31\u0e1a3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006633\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e1f\u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006633 \u0e1a\u0e08.\u0e40\u0e0a\u0e1f\u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 235  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006641\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35 \u0e41\u0e25\u0e19\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006641 \u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35 \u0e41\u0e25\u0e19\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\u0e2b\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e27\u0e19\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 257  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006650\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c289 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006650 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c289 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e2a\u0e34\u0e1a\u0e25\u0e49\u0e2d \u0e23\u0e16\u0e01\u0e30\u0e1a\u0e30 \u0e23\u0e16\u0e2b\u0e31\u0e27\u0e25\u0e32\u0e01 \u0e23\u0e16\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u904b\u8f38\u30fb\u7269\u6d41 131  \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569006692\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e14\u0e25\u0e42\u0e25 \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"24320\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"24320\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006692 \u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e14\u0e25\u0e42\u0e25 \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 24320 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e2b\u0e25\u0e48\u0e2d\u0e42\u0e25\u0e2b\u0e30 \u0e2b\u0e25\u0e2d\u0e21 \u0e2b\u0e25\u0e48\u0e2d \u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e15\u0e31\u0e14 \u0e01\u0e25\u0e36\u0e07 \u0e01\u0e31\u0e14 \u0e40\u0e08\u0e32\u0e30 \u0e02\u0e31\u0e14 \u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e0a\u0e38\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e1c\u0e34\u0e27 \u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e32\u0e01\u0e17\u0e2d\u0e07\u0e2a\u0e31\u0e21\u0e24\u0e17\u0e18\u0e34\u0e4c \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2d\u0e30\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e42\u0e25\u0e2b\u0e30\u0e1c\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 37\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0743569000862\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e23\u0e22\u0e4c \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10212\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10212\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000862 \u0e2b\u0e08.\u0e40\u0e23\u0e22\u0e4c \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e1f\u0e39\u0e49\u0e14 2569-07-01 1000000 10212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 53\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0743569000871\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e2b\u0e21\u0e32\u0e22 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10211\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10211\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000871 \u0e2b\u0e08.\u0e2a\u0e21\u0e2b\u0e21\u0e32\u0e22 \u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14 2569-07-01 1000000 10211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u88fd\u9020 104\/415  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569006927\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e23\u0e31\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569006927 \u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e23\u0e31\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e23\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 (central kitchen) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2a\u0e32\u0e02\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0745569006935\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e25 88 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569006935 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e25 88 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 64\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0755569000511\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0755569000511 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e04\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e23\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23   \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 119\/26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0765569001364\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35 \u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001364 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35 \u0e0b\u0e31\u0e21\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e44\u0e14\u0e49\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49 \u0e42\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0b\u0e2d\u0e1f\u0e17\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e14\u0e49\u0e27\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e1a\u0e04\u0e49\u0e19 (retrieval process) \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30 \u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21 \u60c5\u5831\u901a\u4fe1\u30fbit 153  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569002832\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e1a\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002832 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e1a\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e19\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 12  \u0e0b\u0e2d\u0e22 2 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e2d\u0e07 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e08\u0e34\u0e15 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0775569002841\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e31\u0e1a\u0e2a\u0e30\u0e41\u0e01 \u0e42\u0e04\u0e42\u0e04\u0e48 \u0e41\u0e21\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"13930\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"13930\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002841 \u0e1a\u0e08.\u0e17\u0e31\u0e1a\u0e2a\u0e30\u0e41\u0e01 \u0e42\u0e04\u0e42\u0e04\u0e48 \u0e41\u0e21\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 13930 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e43\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e43\u0e22\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 (coconut fiber mat) \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u88fd\u9020 47\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0803569000888\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e34\u0e15\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07895\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000888 \u0e2b\u0e08.\u0e21\u0e34\u0e15\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07895 2569-07-01 1000000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e14\u0e34\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e07\u0e32\u0e19\u0e02\u0e38\u0e14 \u0e16\u0e21 \u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d \u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e02\u0e38\u0e14\u0e04\u0e39 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2b\u0e34\u0e19 \u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e2b\u0e34\u0e19 \u0e2f\u0e25\u0e2f \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e16\u0e19\u0e19\u0e41\u0e25\u0e30\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e23\u0e31\u0e49\u0e27 \u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1c\u0e49\u0e27\u0e16\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e01\u0e32\u0e23\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u5efa\u8a2d 277  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002441\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e32\u0e07\u0e14\u0e35 \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e42\u0e19\u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002441 \u0e1a\u0e08.\u0e22\u0e32\u0e07\u0e14\u0e35 \u0e2d\u0e30\u0e42\u0e01\u0e23\u0e42\u0e19\u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e23\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002459\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45203\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45203\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002459 \u0e1a\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 45203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e25\u0e49\u0e32\u0e07 \u0e2d\u0e31\u0e14 \u0e09\u0e35\u0e14 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 13\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002483\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 69 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002483 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39 \u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 69 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e19\u0e33\u0e21\u0e32\u0e08\u0e31\u0e14\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e25\u0e07\u0e43\u0e19\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e0b\u0e36\u0e48\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e4d\u0e49\u0e32 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e32\u0e07\u0e23\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e17\u0e48\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e22\u0e32\u0e19\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e43\u0e2b\u0e49\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e0a\u0e31\u0e48\u0e07\u0e19\u0e4d\u0e49\u0e32\u0e2b\u0e19\u0e31\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e38\u0e48\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e38\u0e1a\u0e2d\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 gps \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 75\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0815569002009\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e23\u0e32 \u0e25\u0e31\u0e01\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002009 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e23\u0e32 \u0e25\u0e31\u0e01\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u5bbf\u6cca\u30fb\u98f2\u98df 271  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569012331\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e18\u0e32\u0e19\u0e32\u0e2a \u0e44\u0e04\u0e23\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012331 \u0e1a\u0e08.\u0e2d\u0e32\u0e18\u0e32\u0e19\u0e32\u0e2a \u0e44\u0e04\u0e23\u0e2d\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 125\/510  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569012349\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e30\u0e21\u0e49\u0e32\u0e22 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012349 \u0e1a\u0e08.\u0e25\u0e30\u0e21\u0e49\u0e32\u0e22 \u0e1a\u0e34\u0e25\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c  \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 84\/28  \u0e16\u0e19\u0e19\u0e15\u0e30\u0e01\u0e31\u0e48\u0e27\u0e1b\u0e48\u0e32 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569009941\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569009941 \u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 7\/87-88  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569009968\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e32\u0e14\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569009968 \u0e1a\u0e08.\u0e21\u0e34\u0e23\u0e32\u0e14\u0e32 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 89\/121  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e42\u0e19\u0e42\u0e27\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569009984\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569009984 \u0e1a\u0e08.\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 168\/421  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c - \u0e1b\u0e32\u0e01\u0e19\u0e49\u0e33 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010001\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e32\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010001 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e32\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e2a\u0e21\u0e04\u0e27\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u4e0d\u52d5\u7523 142\/17   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 r.47 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010010\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e1988 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010010 \u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e1988 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u5efa\u8a2d 72\/26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0865569001134\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e17\u0e35 \u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001134 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e17\u0e35 \u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 400  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001433\",\"name_th\":\"\u0e2b\u0e08.\u0e13\u0e31\u0e10\u0e11\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001433 \u0e2b\u0e08.\u0e13\u0e31\u0e10\u0e11\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e4c 2569-07-01 1000000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e22\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e22\u0e32\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e22\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e27\u0e0a\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e0b\u0e2d\u0e226 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005139\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e2a\u0e41\u0e1b\u0e19 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005139 \u0e1a\u0e08.\u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e2a\u0e41\u0e1b\u0e19 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 24  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e0b\u0e2d\u0e22 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005155\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e0d\u0e27\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005155 \u0e1a\u0e08.\u0e0a\u0e32\u0e0d\u0e27\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e0b\u0e2d\u0e22 5 \u0e16\u0e19\u0e19\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e2d\u0e07 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005163\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e23\u0e34 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005163 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e23\u0e34 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 23\/1  \u0e0b\u0e2d\u0e22 11\/1 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005171\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46204\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46204\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005171 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46204 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0923569000186\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e35 1997\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0923569000186 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e35 1997 2569-07-01 1000000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e42\u0e14\u0e22\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e2d\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c (\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0925569000943\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c  \u0e1f\u0e34\u0e14\u0e21\u0e34\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1000000,\"capital_display\":\"1,000,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569000943 \u0e1a\u0e08.\u0e40\u0e2d \u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c  \u0e1f\u0e34\u0e14\u0e21\u0e34\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 1000000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e1b\u0e25\u0e32\u0e1b\u0e48\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0105569127843\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e15\u0e15\u0e4c\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":995004,\"capital_display\":\"995,004 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127843 \u0e1a\u0e08.\u0e08\u0e34\u0e15\u0e15\u0e4c\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 995004 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u4e0d\u52d5\u7523 11\/4  \u0e0b\u0e2d\u0e22 \u0e01\u0e34\u0e48\u0e07\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e2d\u0e31\u0e01\u0e29\u0e23 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0673569000570\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e47\u0e17 \u0e2a\u0e44\u0e21\u0e25\u0e4c\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":900000,\"capital_display\":\"900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0673569000570 \u0e2b\u0e08.\u0e40\u0e1e\u0e47\u0e17 \u0e2a\u0e44\u0e21\u0e25\u0e4c 2569-07-29 900000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2e\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0203569003289\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e22\u0e32 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":900000,\"capital_display\":\"900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003289 \u0e2b\u0e08.\u0e21\u0e32\u0e22\u0e32 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 2569-07-25 900000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e40\u0e25\u0e47\u0e1a\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e25\u0e47\u0e1a\u0e40\u0e17\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 21\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001367\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e2a \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":900000,\"capital_display\":\"900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01301\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01301\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001367 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e2a \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 2569-07-25 900000 01301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e0a\u0e48\u0e2d\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u8fb2\u6797\u6c34\u7523 559\/182  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569022189\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e32\u0e42\u0e27\u0e49\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":900000,\"capital_display\":\"900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022189 \u0e1a\u0e08.\u0e23\u0e32\u0e42\u0e27\u0e49\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 900000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110\/49  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e35\u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e27\u0e14\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 1 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0303569002583\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e2d\u0e14\u0e31\u0e21\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":900000,\"capital_display\":\"900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47742\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47742\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002583 \u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e2d\u0e14\u0e31\u0e21\u0e2a\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-07 900000 47742 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0633569000642\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e34\u0e23\u0e31\u0e0d\u0e1a\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e27\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":900000,\"capital_display\":\"900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000642 \u0e2b\u0e08.\u0e2b\u0e34\u0e23\u0e31\u0e0d\u0e1a\u0e48\u0e2d\u0e41\u0e01\u0e49\u0e27\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 2569-07-01 900000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0843569001272\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04 \u0e17\u0e35 \u0e17\u0e35 2014\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":900000,\"capital_display\":\"900,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001272 \u0e2b\u0e08.\u0e40\u0e04 \u0e17\u0e35 \u0e17\u0e35 2014 2569-07-01 900000 46699 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04-\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23\/207  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0663569000634\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e01\u0e0b\u0e48\u0e32 \u0e40\u0e17\u0e04\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0663569000634 \u0e2b\u0e08.\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e01\u0e0b\u0e48\u0e32 \u0e40\u0e17\u0e04 2569-07-28 800000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569139531\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"15121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"15121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139531 \u0e1a\u0e08.\u0e04\u0e34\u0e27\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 800000 15121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u88fd\u9020 382  \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 40 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027725\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e40\u0e17\u0e0469 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027725 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e40\u0e17\u0e0469 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 800000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e1c\u0e25\u0e34\u0e15\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u60c5\u5831\u901a\u4fe1\u30fbit 67\/105  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0903569001751\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001751 \u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e27\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-21 800000 47113 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e2a\u0e39\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e30\u0e40\u0e01\u0e29 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0115569023983\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023983 \u0e1a\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 800000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e38\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e49\u0e32\u0e27\u0e41\u0e01\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 12\/7   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 kk7,kk8 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569131875\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e0b\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131875 \u0e1a\u0e08.\u0e40\u0e08\u0e0b\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 800000 29309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 34\/18  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e3255\/8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0745569007231\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e1a\u0e35 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46316\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46316\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007231 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e1a\u0e35 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 800000 46316 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e21\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 75\/179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002042\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e32\u0e19\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002042 \u0e2b\u0e08.\u0e1e\u0e32\u0e19\u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-06 800000 71202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e02\u0e19\u0e32\u0e14\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e48\u0e32\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19\u0e2a\u0e35\u0e48\u0e1e\u0e31\u0e19\u0e01\u0e34\u0e42\u0e25\u0e01\u0e23\u0e31\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e29\u0e35\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 251  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0803569000900\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e07\u0e29\u0e4c\u0e1e\u0e23\u0e23\u0e13 \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000900 \u0e2b\u0e08.\u0e1e\u0e07\u0e29\u0e4c\u0e1e\u0e23\u0e23\u0e13 \u0e41\u0e2d\u0e2a\u0e40\u0e2a\u0e17 2569-07-06 800000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e04\u0e19\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e23\u0e30\u0e17\u0e33\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07  \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e39\u0e48\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 42\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0463569000695\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000695 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38 2569-07-03 800000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0215569008754\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2d\u0e2a \u0e44\u0e25\u0e1f\u0e4c\u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":800000,\"capital_display\":\"800,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0215569008754 \u0e1a\u0e08.\u0e1e\u0e2d\u0e2a \u0e44\u0e25\u0e1f\u0e4c\u0e44\u0e0b\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 800000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 2\/2  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0443569000911\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e0b\u0e35 \u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e44\u0e25\u0e17\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000911 \u0e2b\u0e08.\u0e40\u0e2d\u0e0b\u0e35\u0e0b\u0e35 \u0e2a\u0e15\u0e23\u0e35\u0e17 \u0e44\u0e25\u0e17\u0e4c 2569-07-27 700000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e44\u0e1f\u0e16\u0e19\u0e19 \u0e42\u0e04\u0e21\u0e44\u0e1f \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c(\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c) \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e1b\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e1e\u0e23\u0e30-\u0e42\u0e01\u0e2a\u0e38\u0e21 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0203569003271\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2e\u0e21\u0e04\u0e25\u0e31\u0e1a \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003271 \u0e2b\u0e08.\u0e42\u0e2e\u0e21\u0e04\u0e25\u0e31\u0e1a \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c 2569-07-25 700000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0903569001727\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e31\u0e27\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e2d\u0e42\u0e23\u0e21\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001727 \u0e2b\u0e08.\u0e2b\u0e31\u0e27\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e2d\u0e42\u0e23\u0e21\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 2569-07-21 700000 20232 : \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e2a\u0e21\u0e2b\u0e31\u0e27\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e2d\u0e42\u0e23\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e19\u0e32\u0e21\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 (oem) \u88fd\u9020 33\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0413569001659\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001659 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c 2569-07-20 700000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e0a\u0e27\u0e4c\u0e23\u0e39\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e2a\u0e14 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0b\u0e37\u0e49\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u5bbf\u6cca\u30fb\u98f2\u98df 689  \u0e16\u0e19\u0e19\u0e42\u0e1e\u0e28\u0e23\u0e35 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0143569001198\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001198 \u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e40\u0e04 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-14 700000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 22\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0503569004894\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e32\u0e41\u0e1f\u0e19\u0e34\u0e22\u0e21\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004894 \u0e2b\u0e08.\u0e01\u0e32\u0e41\u0e1f\u0e19\u0e34\u0e22\u0e21\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 2569-07-14 700000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e21\u0e19\u0e39\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 18\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569132464\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a2026 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132464 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e2a2026 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 700000 47595 )\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e15\u0e32\u0e21\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 13  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e0d\u0e01\u0e34\u0e0829\u0e41\u0e22\u0e016 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e0d\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0733569001044\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e17\u0e38\u0e1a\u0e15\u0e36\u0e01  \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43110\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43110\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001044 \u0e2b\u0e08.\u0e1e\u0e34\u0e0a\u0e34\u0e15\u0e17\u0e38\u0e1a\u0e15\u0e36\u0e01  \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 2569-07-13 700000 43110 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e17\u0e38\u0e1a \u0e17\u0e33\u0e25\u0e32\u0e22 \u0e23\u0e37\u0e49\u0e2d\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0105569131841\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e1e\u0e4c\u0e14\u0e23\u0e35\u0e21 \u0e42\u0e19\u0e41\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131841 \u0e1a\u0e08.\u0e44\u0e1e\u0e1e\u0e4c\u0e14\u0e23\u0e35\u0e21 \u0e42\u0e19\u0e41\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 700000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e41\u0e1f\u0e19\u0e21\u0e34\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 92\/5  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e23\u0e18\u0e32\u0e19\u0e35 2 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e18\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569002746\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e38\u0e07\u0e14\u0e33\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e1f\u0e23\u0e38\u0e4a\u0e15\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":700000,\"capital_display\":\"700,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002746 \u0e2b\u0e08.\u0e25\u0e38\u0e07\u0e14\u0e33\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e1f\u0e23\u0e38\u0e4a\u0e15 2569-07-01 700000 46313 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73\/35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0503569005041\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e2d\u0e2a\u0e38\u0e02\u0e1e\u0e2d\u0e14\u0e35\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":650000,\"capital_display\":\"650,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005041 \u0e2b\u0e08.\u0e1e\u0e2d\u0e2a\u0e38\u0e02\u0e1e\u0e2d\u0e14\u0e35 2569-07-20 650000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 9\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569001984\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e15\u0e2d\u0e35\u0e0b\u0e35\u0e17\u0e35\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":650000,\"capital_display\":\"650,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01301\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01301\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569001984 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e15\u0e2d\u0e35\u0e0b\u0e35\u0e17\u0e35 2569-07-01 650000 01301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u8fb2\u6797\u6c34\u7523 265  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e48\u0e32\u0e40\u0e2b\u0e35\u0e22\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569142761\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e17245 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142761 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e17245 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 600000 96101 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e34\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 768\/248  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c73 \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e2338 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0902569000045\",\"name_th\":\"\u0e2b\u0e2a.\u0e40\u0e08\u0e2a\u0e42\u0e0b\u0e48\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0902569000045 \u0e2b\u0e2a.\u0e40\u0e08\u0e2a\u0e42\u0e0b\u0e48 2569-07-31 600000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 309\/2  \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e19\u0e2d\u0e01 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0673569000561\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2d.\u0e17\u0e35 \u0e21\u0e32\u0e22\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95120\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95120\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0673569000561 \u0e2b\u0e08.\u0e44\u0e2d.\u0e17\u0e35 \u0e21\u0e32\u0e22 2569-07-29 600000 95120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e2d\u0e2a\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569008079\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e17\u0e04\u0e41\u0e2d\u0e19\u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e19\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95210\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95210\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008079 \u0e2b\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e17\u0e04\u0e41\u0e2d\u0e19\u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e19 2569-07-25 600000 95210 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 upgrade, training \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b. \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 111\/141  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e36\u0e07\u0e1a\u0e31\u0e27 \u0e0b\u0e2d\u0e22 20\/1 \u0e16\u0e19\u0e19\u0e04\u0e38\u0e49\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0663569000596\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e39\u0e43\u0e2a \u0e44\u0e2d.\u0e17\u0e35\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95110\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95110\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0663569000596 \u0e2b\u0e08.\u0e0a\u0e39\u0e43\u0e2a \u0e44\u0e2d.\u0e17\u0e35 2569-07-24 600000 95110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 270\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0505569016461\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e01\u0e01\u0e35\u0e49\u0e0a\u0e47\u0e2d\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016461 \u0e1a\u0e08.\u0e21\u0e34\u0e01\u0e01\u0e35\u0e49\u0e0a\u0e47\u0e2d\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 600000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e2d\u0e40\u0e17\u0e21\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e43\u0e19\u0e40\u0e01\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e2b\u0e31\u0e2a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 630\/75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0103569007722\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\u0e41\u0e04\u0e23\u0e4c2489\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007722 \u0e2b\u0e08.\u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49\u0e41\u0e04\u0e23\u0e4c2489 2569-07-18 600000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 221\/146  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 0 \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e306\u0e41\u0e22\u0e011-4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569003165\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e1f\u0e19 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e2d.\u0e17\u0e35\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95120\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95120\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003165 \u0e2b\u0e08.\u0e42\u0e1f\u0e19 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e2d.\u0e17\u0e35 2569-07-18 600000 95120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 187  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003173\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e14\u0e35 1\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003173 \u0e2b\u0e08.\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e14\u0e35 1 2569-07-18 600000 81210 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e01\u0e23\u0e30\u0e08\u0e01 \u0e01\u0e33\u0e08\u0e31\u0e14\u0e44\u0e23\u0e1d\u0e38\u0e48\u0e19 \u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e42\u0e23\u0e04 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 187  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0653569001142\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e17\u0e04\u0e32\u0e2a\u0e38\u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01271\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01271\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001142 \u0e2b\u0e08.\u0e42\u0e17\u0e04\u0e32\u0e2a\u0e38\u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-17 600000 01271 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e14 \u0e1c\u0e2a\u0e21 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32 \u0e1c\u0e07\u0e0a\u0e32 \u0e1c\u0e07\u0e21\u0e31\u0e17\u0e09\u0e30 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e07\u0e0a\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e21\u0e31\u0e17\u0e09\u0e30 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e39\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e41\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e0a\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u8fb2\u6797\u6c34\u7523 56\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0473569000920\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 1995\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000920 \u0e2b\u0e08.\u0e42\u0e0a\u0e04\u0e28\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 1995 2569-07-15 600000 47190 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e2b\u0e21\u0e28\u0e34\u0e23\u0e34 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0183569000272\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e1e\u0e47\u0e17 789\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0183569000272 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e1e\u0e47\u0e17 789 2569-07-13 600000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 8  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 46 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0203569003017\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e34\u0e27 \u0e41\u0e17\u0e17\u0e17\u0e39\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003017 \u0e2b\u0e08.\u0e19\u0e34\u0e27 \u0e41\u0e17\u0e17\u0e17\u0e39 2569-07-13 600000 47190 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e01\u0e25\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e0a\u0e38\u0e14\u0e2a\u0e31\u0e01 \u0e2b\u0e21\u0e36\u0e01\u0e2a\u0e31\u0e01 \u0e40\u0e02\u0e47\u0e21\u0e2a\u0e31\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e01 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e25\u0e2d\u0e01\u0e25\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157\/164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0633569000715\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e31\u0e19\u0e22\u0e32 \u0e17\u0e31\u0e27\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000715 \u0e2b\u0e08.\u0e01\u0e31\u0e19\u0e22\u0e32 \u0e17\u0e31\u0e27\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-11 600000 49329 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 315\/7 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e34\u0e21\u0e40\u0e21\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0623569000693\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e2d\u0e07 898\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42201\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42201\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000693 \u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e2d\u0e07 898 2569-07-09 600000 42201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e1d\u0e32\u0e22\u0e19\u0e49\u0e33\u0e25\u0e49\u0e19 \u0e1d\u0e32\u0e22\u0e01\u0e31\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e04\u0e31\u0e19\u0e01\u0e31\u0e49\u0e19\u0e19\u0e49\u0e33 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e15\u0e25\u0e34\u0e48\u0e07\u0e1e\u0e31\u0e07 \u0e02\u0e38\u0e14\u0e25\u0e2d\u0e01\u0e04\u0e39\u0e04\u0e25\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e1a\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e27\u0e31\u0e0a\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e35\u0e14\u0e02\u0e27\u0e32\u0e07\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e19\u0e49\u0e33\u0e17\u0e48\u0e27\u0e21\u0e19\u0e49\u0e33\u0e41\u0e25\u0e49\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 315\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0715569002522\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e40\u0e22\u0e48\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002522 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e40\u0e22\u0e48\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 600000 47912 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 \u0e25\u0e39\u0e01\u0e01\u0e27\u0e32\u0e14 \u0e25\u0e39\u0e01\u0e2d\u0e21 \u0e17\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 128\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0573569002051\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e31\u0e22\u0e2d\u0e49\u0e32\u0e22 \u0e1e\u0e25\u0e31\u0e2a\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002051 \u0e2b\u0e08.\u0e2a\u0e21\u0e31\u0e22\u0e2d\u0e49\u0e32\u0e22 \u0e1e\u0e25\u0e31\u0e2a 2569-07-06 600000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 915\/5  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569125751\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e04\u0e2d\u0e25 \u0e0b\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125751 \u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e04\u0e2d\u0e25 \u0e0b\u0e34\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 600000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e13 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e23\u0e31\u0e01\u0e29\u0e32\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u533b\u7642\u30fb\u798f\u7949 78  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0143569001112\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e23\u0e30\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17168\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":600000,\"capital_display\":\"600,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001112 \u0e2b\u0e08.\u0e1e\u0e35\u0e23\u0e30\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e2d\u0e2d\u0e42\u0e15\u0e49\u0e1e\u0e32\u0e23\u0e4c\u0e17168 2569-07-01 600000 45103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0503569004533\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e38\u0e19\u0e02\u0e19\u0e21\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":550000,\"capital_display\":\"550,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004533 \u0e2b\u0e08.\u0e15\u0e38\u0e19\u0e02\u0e19\u0e21 2569-07-09 550000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e02\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e02\u0e19\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0833569000551\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":550000,\"capital_display\":\"550,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0833569000551 \u0e2b\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d 2569-07-08 550000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 70\/122  \u0e2d\u0e32\u0e04\u0e32\u0e231  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 70\/122 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e323 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1c\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d8 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e49\u0e32\u0e1f\u0e49\u0e32\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0203569003181\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e1f\u0e34\u0e19\u0e34\u0e0a\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500900,\"capital_display\":\"500,900 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003181 \u0e2b\u0e08.\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e1f\u0e34\u0e19\u0e34\u0e0a 2569-07-20 500900 46695 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e41\u0e25\u0e30\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48 (\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e17\u0e2d\u0e14\u0e0b\u0e49\u0e33) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0563569000619\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e21\u0e17\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500100,\"capital_display\":\"500,100 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0563569000619 \u0e2b\u0e08.\u0e41\u0e21\u0e17\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f 2569-07-07 500100 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e01\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d (mv) \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0105569142753\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e34\u0e07 \u0e0a\u0e34\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e23\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142753 \u0e1a\u0e08.\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e34\u0e07 \u0e0a\u0e34\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e23\u0e32\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 315\/414  \u0e0b\u0e2d\u0e22 19 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e18\u0e39\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142826\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e01\u0e21\u0e30\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142826 \u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e01\u0e21\u0e30\u0e22\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 466\/23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e14\u0e4c\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142842\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1f\u0e04\u0e31\u0e2a\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142842 \u0e1a\u0e08.\u0e44\u0e1f\u0e04\u0e31\u0e2a\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 3069\/1  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143059\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e40\u0e01\u0e23\u0e17\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143059 \u0e1a\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e40\u0e01\u0e23\u0e17\u0e40\u0e27\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 38   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e0b\u0e2d\u0e22 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143288\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e21\u0e13\u0e32 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143288 \u0e1a\u0e08.\u0e2d\u0e31\u0e21\u0e13\u0e32 \u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/226  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002615\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e23\u0e31\u0e0a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002615 \u0e2b\u0e08.\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e27\u0e34\u0e23\u0e31\u0e0a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-31 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28\/92  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002623\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e1e\u0e32\u0e23\u0e4c\u0e17 839\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002623 \u0e2b\u0e08.\u0e1a\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e1e\u0e32\u0e23\u0e4c\u0e17 839 2569-07-31 500000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e16\u0e41\u0e17\u0e23\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e01\u0e48\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 333  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569023509\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023509 \u0e1a\u0e08.\u0e17\u0e39\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e4d\u0e49\u0e32 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 30\/569  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569039650\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e01 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039650 \u0e1a\u0e08.\u0e40\u0e2d\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e01 \u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e32\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e0a\u0e31\u0e22\u0e1e\u0e23\u0e27\u0e34\u0e18\u0e35 25 \u0e16\u0e19\u0e19\u0e0a\u0e31\u0e22\u0e1e\u0e23\u0e27\u0e34\u0e18\u0e35 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0345569003450\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003450 \u0e1a\u0e08.\u0e04\u0e25\u0e31\u0e07\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 637\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0353569000530\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e2a\u0e01\u0e38\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0353569000530 \u0e2b\u0e08.\u0e41\u0e2a\u0e07\u0e2a\u0e01\u0e38\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-31 500000 41001 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u5efa\u8a2d 23\/17  \u0e0b\u0e2d\u0e22 \u0e42\u0e19\u0e19\u0e15\u0e32\u0e252 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0393569000394\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e34\u0e19\u0e23\u0e35\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000394 \u0e2b\u0e08.\u0e01\u0e34\u0e19\u0e23\u0e35\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2569-07-31 500000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 359  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0415569004099\",\"name_th\":\"\u0e1a\u0e08.639 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004099 \u0e1a\u0e08.639 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e01\u0e14\u0e31\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e16\u0e21\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32  \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569005343\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005343 \u0e2b\u0e08.\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 2569-07-31 500000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e1d\u0e48\u0e32\u0e40\u0e17\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e19\u0e27\u0e14\u0e04\u0e2d \u0e1a\u0e48\u0e32 \u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 46\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0643569000537\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2e\u0e0a\u0e34\u0e25\u0e25\u0e35\u0e48\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0643569000537 \u0e2b\u0e08.\u0e44\u0e2e\u0e0a\u0e34\u0e25\u0e25\u0e35\u0e48 2569-07-31 500000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 57\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0725569002263\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e13 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002263 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e2d\u0e23\u0e38\u0e13 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 3\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0905569006445\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e1f\u0e32\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006445 \u0e1a\u0e08.\u0e1f\u0e32\u0e1f\u0e32\u0e23\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17  \u0e0b\u0e2d\u0e22 \u0e01\u0e25\u0e31\u0e1a\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569001184\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e19\u0e19\u0e35\u0e48 \u0e04\u0e25\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001184 \u0e1a\u0e08.\u0e08\u0e35\u0e19\u0e19\u0e35\u0e48 \u0e04\u0e25\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 500000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0103569008192\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1a\u0e35 \u0e40\u0e1a\u0e04\u0e48\u0e2d\u0e19\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47111\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47111\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008192 \u0e2b\u0e08.\u0e1e\u0e35\u0e1a\u0e35 \u0e40\u0e1a\u0e04\u0e48\u0e2d\u0e19 2569-07-30 500000 47111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 481\/374  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142524\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a.\u0e27\u0e2d\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142524 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a.\u0e27\u0e2d\u0e23\u0e4c\u0e21\u0e21\u0e34\u0e48\u0e07 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 500000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c  \u0e42\u0e23\u0e07\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c  \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e21\u0e2b\u0e23\u0e2a\u0e1e\u0e2d\u0e37\u0e48\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32  \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e42\u0e1a\u0e27\u0e4c\u0e25\u0e34\u0e48\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 364  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e32\u0e40\u0e2d\u0e2a\u0e42\u0e15\u0e23 07 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e49\u0e19\u0e0b\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e27\u0e34\u0e16\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142672\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e2d\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142672 \u0e1a\u0e08.\u0e42\u0e23\u0e2d\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 500000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e04\u0e25\u0e34\u0e19\u0e34\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u533b\u7642\u30fb\u798f\u7949 98\/146  \u0e16\u0e19\u0e19\u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569025196\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2e\u0e0b\u0e38\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025196 \u0e1a\u0e08.\u0e42\u0e2e\u0e0b\u0e38\u0e22 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0a\u0e32 \u0e0a\u0e32\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e21\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2b\u0e35\u0e1a\u0e2b\u0e48\u0e2d \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/989  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569023444\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e32\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023444 \u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e32\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 500000 86201 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u533b\u7642\u30fb\u798f\u7949 1\/13  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e2d\u0e40\u0e27\u0e19\u0e34\u0e27 (2) \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 63\/1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0173569000183\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0173569000183 \u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c 2569-07-30 500000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01\u0e1b\u0e38\u0e4b\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0463569000792\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e47\u0e21.\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000792 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e47\u0e21.\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-30 500000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 80  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0205569039439\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e20\u0e31\u0e04\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039439 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e20\u0e31\u0e04\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 500000 75000 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 91\/91,91\/92  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002390\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e07\u0e29\u0e4c\u0e17\u0e2d\u0e07\u0e27\u0e07\u0e29\u0e4c\u0e41\u0e01\u0e49\u0e27 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002390 \u0e1a\u0e08.\u0e27\u0e07\u0e29\u0e4c\u0e17\u0e2d\u0e07\u0e27\u0e07\u0e29\u0e4c\u0e41\u0e01\u0e49\u0e27 \u0e44\u0e1a\u0e42\u0e2d\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 500000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22, \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01, \u0e1b\u0e38\u0e4b\u0e22 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0483569000555\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e40\u0e0b\u0e35\u0e22\u0e04\u0e2d\u0e1b 789\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000555 \u0e2b\u0e08.\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e40\u0e0b\u0e35\u0e22\u0e04\u0e2d\u0e1b 789 2569-07-29 500000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 250  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0503569005319\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e17\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005319 \u0e2b\u0e08.\u0e40\u0e2d\u0e1a\u0e35\u0e17\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-29 500000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 131\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569002280\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e47\u0e01\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48\u0e2a\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002280 \u0e2b\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e47\u0e01\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48\u0e2a\u0e14 2569-07-29 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569142206\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142206 \u0e1a\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e07\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e07\u0e32\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e02\u0e49\u0e32\u0e07\u0e15\u0e49\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 41\/327  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 111 \u0e41\u0e22\u0e01 3-1-6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024998\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e1e \u0e04\u0e39\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024998 \u0e1a\u0e08.\u0e04\u0e35\u0e1e \u0e04\u0e39\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 500000 46691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e22\u0e49\u0e2d\u0e21\u0e2a\u0e35 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e42\u0e25\u0e2b\u0e30 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e19\u0e32\u0e42\u0e19\u0e40\u0e0b\u0e25\u0e32\u0e21\u0e34\u0e04 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e1c\u0e34\u0e27 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e15\u0e34\u0e14\u0e01\u0e23\u0e30\u0e08\u0e01  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21  \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 116\/210  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569023371\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023371 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 500000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e21\u0e48 \u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54\/189  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004954\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e0b\u0e31\u0e04\u0e40\u0e0b\u0e17 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49331\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49331\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004954 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e0b\u0e31\u0e04\u0e40\u0e0b\u0e17 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 500000 49331 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e17\u0e32\u0e07\u0e16\u0e19\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0403569003350\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003350 \u0e2b\u0e08.\u0e1a\u0e35\u0e40\u0e04\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e1b\u0e15\u0e4c 2569-07-28 500000 46691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 445\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0673569000553\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e19\u0e34\u0e0a\u0e22\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0673569000553 \u0e2b\u0e08.\u0e27\u0e32\u0e19\u0e34\u0e0a\u0e22\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 2569-07-28 500000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 204  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0705569003448\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e35\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47893\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47893\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003448 \u0e1a\u0e08.\u0e25\u0e35\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 500000 47893 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e2a\u0e21\u0e38\u0e14\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e08\u0e31\u0e14\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e1e\u0e25\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23 \u0e19\u0e27\u0e19\u0e34\u0e22\u0e32\u0e22 \u0e15\u0e4d\u0e32\u0e23\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e42\u0e25\u0e01 \u0e1e\u0e08\u0e19\u0e32\u0e19\u0e38\u0e01\u0e23\u0e21 \u0e2a\u0e32\u0e23\u0e32\u0e19\u0e38\u0e01\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e25\u0e48\u0e21\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e25\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 (e-book) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0843569001451\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001451 \u0e2b\u0e08.\u0e27\u0e23\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c 2569-07-28 500000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e49\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u4e0d\u52d5\u7523 40\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569141498\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 2020 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141498 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 2020 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 28299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u88fd\u9020 83\/211  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e21\u0e27\u0e32 20 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141528\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e27\u0e35 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141528 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e27\u0e35 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u88fd\u9020 30\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e19\u0e32\u0e2a\u0e19\u0e18\u0e34\u0e4c\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e2268 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141587\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e0b\u0e35 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141587 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e0b\u0e35 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1a\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e49\u0e01 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15  \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u5bbf\u6cca\u30fb\u98f2\u98df 15\/33  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141871\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e1e\u0e2d\u0e22\u0e15\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141871 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e1e\u0e48\u0e19\u0e1e\u0e2d\u0e22\u0e15\u0e4c \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 70201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 34-36  \u0e0b\u0e2d\u0e22 \u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c 18\/7 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141960\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e28\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141960 \u0e1a\u0e08.\u0e40\u0e01\u0e28\u0e23 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e27\u0e19 \u0e2a\u0e27\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e39\u0e01 \u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2b\u0e0d\u0e49\u0e32 \u0e01\u0e33\u0e08\u0e31\u0e14\u0e27\u0e31\u0e0a\u0e1e\u0e37\u0e0a \u0e43\u0e2a\u0e48\u0e1b\u0e38\u0e4b\u0e22 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e14\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 79  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b.28 \u0e41\u0e22\u0e01 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024882\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e1f \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024882 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e1f \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 69200 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 112\/11  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e14\u0e48\u0e32\u0e19 18 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024904\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e42\u0e23\u0e48 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10801\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10801\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024904 \u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e42\u0e23\u0e48 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 10801 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e38\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u88fd\u9020 896  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002313\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25 \u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002313 \u0e2b\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e25 \u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21 2569-07-27 500000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e07\u0e07\u0e32\u0e19\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e35\u0e48\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e40\u0e14\u0e47\u0e01 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 23\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023223\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e17 \u0e2d\u0e2d\u0e14\u0e34\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023223 \u0e1a\u0e08.\u0e42\u0e01\u0e23\u0e17 \u0e2d\u0e2d\u0e14\u0e34\u0e17\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 69200 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 800\/241  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0143569001228\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e17\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001228 \u0e2b\u0e08.\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e17 2569-07-27 500000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e17\u0e31\u0e28\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 100\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001777\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e04\u0e23\u0e31\u0e27\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001777 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e04\u0e23\u0e31\u0e27\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0253569000514\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0253569000514 \u0e2b\u0e08.\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-27 500000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 78\/70  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e2b\u0e30\u0e1a\u0e32\u0e07\u0e40\u0e14\u0e0a\u0e30\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0273569000484\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e40\u0e15\u0e47\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e16\u0e27 1661\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0273569000484 \u0e2b\u0e08.\u0e2a\u0e40\u0e15\u0e47\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e16\u0e27 1661 2569-07-27 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 45  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0303569002966\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002966 \u0e2b\u0e08.\u0e2d\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-27 500000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5efa\u8a2d 202  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e2d\u0e07\u0e15\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0503569005289\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e35. \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38110\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38110\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005289 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e35. \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-27 500000 38110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e22\u0e30\u0e21\u0e39\u0e25\u0e1d\u0e2d\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e02\u0e22\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e0f\u0e34\u0e01\u0e39\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e02\u0e22\u0e30\u0e21\u0e39\u0e25\u0e1d\u0e2d\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e02\u0e22\u0e30 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1d\u0e31\u0e07\u0e01\u0e25\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e23\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e02\u0e22\u0e30\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e01\u0e33\u0e2b\u0e19\u0e14 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 92  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016797\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e1f\u0e25\u0e32\u0e22\u0e2d\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016797 \u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e1f\u0e25\u0e32\u0e22\u0e2d\u0e34\u0e49\u0e07 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (international cargo) \u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e1a\u0e1a door-to-door \u904b\u8f38\u30fb\u7269\u6d41 359\/102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004870\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e41\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004870 \u0e1a\u0e08.\u0e41\u0e21\u0e41\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e17\u0e23\u0e32\u0e22 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46\u0e2a\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0725569002221\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e19\u0e19\u0e17\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01411\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01411\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002221 \u0e1a\u0e08.\u0e42\u0e04\u0e19\u0e19\u0e17\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 01411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e42\u0e04\u0e40\u0e19\u0e37\u0e49\u0e2d \u8fb2\u6797\u6c34\u7523 139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001141\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e0a\u0e31\u0e22\u0e21\u0e07\u0e04\u0e25\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001141 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e0a\u0e31\u0e22\u0e21\u0e07\u0e04\u0e25\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-27 500000 41001 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569008024\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008024 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 500000 47912 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e1c\u0e48\u0e19\u0e42\u0e1f\u0e21\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01 \u0e41\u0e1c\u0e48\u0e19\u0e22\u0e32\u0e07 eva \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e01\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001808\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e28\u0e23\u0e29\u0e10\u0e351991\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001808 \u0e2b\u0e08.\u0e40\u0e28\u0e23\u0e29\u0e10\u0e351991 2569-07-27 500000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0135569023151\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2e\u0e32\u0e2a\u0e4c 126 \u0e1f\u0e32\u0e0b\u0e32\u0e14 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e01\u0e25\u0e32\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023151 \u0e1a\u0e08.\u0e01\u0e23\u0e35\u0e19\u0e40\u0e2e\u0e32\u0e2a\u0e4c 126 \u0e1f\u0e32\u0e0b\u0e32\u0e14 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e01\u0e25\u0e32\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 39\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e16\u0e19\u0e19\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0635569001519\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001519 \u0e1a\u0e08.\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e14\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 500000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c (logistics) \u0e23\u0e31\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e4d\u0e49\u0e32 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e01\u0e23\u0e30\u0e1a\u0e30 \u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 375\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0105569141013\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e17\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85492\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85492\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141013 \u0e1a\u0e08.\u0e21\u0e34\u0e17\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 500000 85492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e04\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e47\u0e2d\u0e1b \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e02\u0e2d\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e48\u0e07 \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e21\u0e2d\u0e07\u0e01\u0e25\u0e1d\u0e31\u0e07\u0e15\u0e31\u0e27 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u6559\u80b2 95\/171  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e25\u0e34\u0e1b\u0e1b\u0e4c \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0743\/1  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 95\/171 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0743\/1 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0743\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141048\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141048 \u0e1a\u0e08.\u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 500000 82302 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 24\/33  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e34\u0e04\u0e42\u0e04\u0e49 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e16\u0e19\u0e19\u0e44\u0e17\u0e22\u0e23\u0e32\u0e21\u0e31\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141145\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e17\u0e4c\u0e44\u0e27\u0e2a\u0e4c \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141145 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e17\u0e4c\u0e44\u0e27\u0e2a\u0e4c \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1155\/105  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e49\u0e19 \u0e1b\u0e25\u0e31\u0e4a\u0e01 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1e\u0e25\u0e22\u0e4c \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25\u0e2a\u0e40\u0e15\u0e0a\u0e31\u0e48\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1155\/105 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141226\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e14\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141226 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e14\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 500000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 73  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 40\/1 \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569003297\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 999\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003297 \u0e2b\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 999 2569-07-25 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 (\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c) \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 369\/81  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e23\u0e34\u0e28\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0323569000599\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e17\u0e22 \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e23\u0e04\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000599 \u0e2b\u0e08.\u0e44\u0e17\u0e22 \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e23\u0e04\u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 2569-07-25 500000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u5efa\u8a2d 191\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e15\u0e30\u0e40\u0e04\u0e35\u0e22\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0503569005262\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005262 \u0e2b\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-25 500000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1e\u0e32\u0e2a\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2d\u0e31\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e17\u0e39\u0e15 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 127\/144  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0705569003413\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e21\u0e35\u0e2a \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003413 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e21\u0e35\u0e2a \u0e40\u0e2d\u0e40\u0e25\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 500000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569139680\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10304\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10304\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139680 \u0e1a\u0e08.\u0e27\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 10304 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e16\u0e19\u0e2d\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e01\u0e27\u0e19 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e0a\u0e48\u0e2d\u0e34\u0e48\u0e21 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e14\u0e2d\u0e07 \u0e1a\u0e4a\u0e27\u0e22 \u0e21\u0e30\u0e21\u0e48\u0e27\u0e07 \u0e21\u0e30\u0e02\u0e32\u0e21 \u0e21\u0e30\u0e02\u0e32\u0e21\u0e41\u0e01\u0e30\u0e40\u0e21\u0e47\u0e14 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 19  \u0e0b\u0e2d\u0e22 \u0e2d\u0e31\u0e28\u0e27\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c 20 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140050\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e13\u0e14\u0e32 \u0e44\u0e17\u0e22\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140050 \u0e1a\u0e08.\u0e1b\u0e13\u0e14\u0e32 \u0e44\u0e17\u0e22\u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1e\u0e27\u0e07\u0e01\u0e38\u0e0d\u0e41\u0e08\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/5  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140131\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0c\u0e2d\u0e25\u0e32\u0e25\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140131 \u0e1a\u0e08.\u0e40\u0e0c\u0e2d\u0e25\u0e32\u0e25\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e2a\u0e23\u0e30\u0e1c\u0e21 \u0e44\u0e14\u0e23\u0e4c\u0e1c\u0e21 \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21 \u0e14\u0e31\u0e14\u0e1c\u0e21 \u0e22\u0e49\u0e2d\u0e21\u0e1c\u0e21 \u0e2d\u0e1a\u0e44\u0e2d\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e28\u0e35\u0e23\u0e29\u0e30 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 17\/8  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e43\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140238\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140238 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e08\u0e31\u0e14\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e23\u0e34\u0e1b\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e17\u0e31\u0e28\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e23\u0e34\u0e1b\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e1a\u0e1a\u0e2b\u0e21\u0e39\u0e48\u0e04\u0e13\u0e30\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1191\/1   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140262\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e2a\u0e40\u0e1b\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140262 \u0e1a\u0e08.\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e2a\u0e40\u0e1b\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 (it) \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1015\/25  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 26 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024572\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35\u0e19\u0e32\u0e04\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024572 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35\u0e19\u0e32\u0e04\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1b\u0e31\u0e19 \u0e22\u0e32\u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13  \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/52  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024611\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e41\u0e0b\u0e14\u0e04\u0e34\u0e27 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024611 \u0e1a\u0e08.\u0e44\u0e2d\u0e41\u0e0b\u0e14\u0e04\u0e34\u0e27 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e04\u0e25\u0e38\u0e21 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e0a\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e43\u0e19\u0e17\u0e33\u0e19\u0e2d\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 135\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027962\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e21\u0e14\u0e34\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027962 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e21\u0e14\u0e34\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46441 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e22\u0e32\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e41\u0e1c\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e40\u0e1e\u0e17\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/5272  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07\u0e18\u0e32\u0e19\u0e35 \u0e40\u0e1f\u0e2a17 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027971\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35.\u0e40\u0e2d\u0e2a.\u0e27\u0e32\u0e22. \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027971 \u0e1a\u0e08.\u0e27\u0e35.\u0e40\u0e2d\u0e2a.\u0e27\u0e32\u0e22. \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 47721 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e41\u0e25\u0e30\u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1a\u0e49\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002623\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e02\u0e43\u0e08 88\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002623 \u0e2b\u0e08.\u0e2a\u0e38\u0e02\u0e43\u0e08 88 2569-07-24 500000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 38\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022928\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e40\u0e01\u0e35\u0e4a\u0e22\u0e27\u0e40\u0e14\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022928 \u0e1a\u0e08.\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e40\u0e01\u0e35\u0e4a\u0e22\u0e27\u0e40\u0e14\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/219  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022952\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e40\u0e1e\u0e47\u0e17\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022952 \u0e1a\u0e08.\u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e40\u0e1e\u0e47\u0e17\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e02\u0e19 \u0e15\u0e31\u0e14\u0e40\u0e25\u0e47\u0e1a \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 98\/19-21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0173569000167\",\"name_th\":\"\u0e2b\u0e08.\u0e28.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 16\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0173569000167 \u0e2b\u0e08.\u0e28.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 16 2569-07-24 500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009831\",\"name_th\":\"\u0e1a\u0e08.\u0e10\u0e32\u0e19\u0e30\u0e14\u0e35\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009831 \u0e1a\u0e08.\u0e10\u0e32\u0e19\u0e30\u0e14\u0e35\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 71\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0255569002136\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e23\u0e34\u0e0a \u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002136 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e23\u0e34\u0e0a \u0e44\u0e23\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007676\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e38\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007676 \u0e1a\u0e08.\u0e08\u0e38\u0e43\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 239\/2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e23\u0e19\u0e32\u0e23\u0e32\u0e22\u0e13\u0e4c 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007684\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e0a\u0e40\u0e04 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007684 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e0a\u0e40\u0e04 \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 236\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0345569003387\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e1e\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003387 \u0e1a\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e1e\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 181  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003955\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e42\u0e04\u0e41\u0e25\u0e47\u0e1a\u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003955 \u0e1a\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e42\u0e04\u0e41\u0e25\u0e47\u0e1a\u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e0b\u0e36\u0e48\u0e07 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 (cctv) \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e2d\u0e01 (access control) \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e1b\u0e35 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e41\u0e23\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 1 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016657\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35 \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016657 \u0e1a\u0e08.\u0e27\u0e35 \u0e40\u0e2e\u0e2d\u0e23\u0e34\u0e40\u0e17\u0e08 \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e42\u0e2e\u0e2a\u0e40\u0e17\u0e25 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 20\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001471\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e1e\u0e35 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001471 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e1e\u0e35 \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 56210 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 79\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004845\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e22\u0e2a\u0e23\u0e49\u0e2d\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004845 \u0e1a\u0e08.\u0e2a\u0e32\u0e22\u0e2a\u0e23\u0e49\u0e2d\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 69200 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e29\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 439\/11-12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0623569000758\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e39\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e1b\u0e34\u0e07\u0e44\u0e27\u0e19\u0e34\u0e25\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000758 \u0e2b\u0e08.\u0e25\u0e39\u0e01\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e1b\u0e34\u0e07\u0e44\u0e27\u0e19\u0e34\u0e25 2569-07-24 500000 74109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e23\u0e49\u0e32\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e44\u0e27\u0e19\u0e34\u0e25 \u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\u0e42\u0e25\u0e2b\u0e30 \u0e2d\u0e30\u0e04\u0e23\u0e34\u0e25\u0e34\u0e04 \u0e1e\u0e25\u0e32\u0e2a\u0e27\u0e39\u0e14 \u0e42\u0e1f\u0e21 \u0e07\u0e32\u0e21\u0e2a\u0e15\u0e34\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 93\/4 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0633569000791\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e0a\u0e32\u0e22 \u0e1e\u0e32\u0e23\u0e27\u0e22\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000791 \u0e2b\u0e08.\u0e2a\u0e21\u0e0a\u0e32\u0e22 \u0e1e\u0e32\u0e23\u0e27\u0e22 2569-07-24 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 409  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002418\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e34\u0e1b\u0e1b\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e40\u0e1a\u0e19\u0e0a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002418 \u0e1a\u0e08.\u0e17\u0e34\u0e1b\u0e1b\u0e34\u0e04\u0e2d\u0e25 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e40\u0e1a\u0e19\u0e0a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 206\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0663569000600\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e32\u0e13\u0e34\u0e28\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e192569\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0663569000600 \u0e2b\u0e08.\u0e1b\u0e32\u0e13\u0e34\u0e28\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e192569 2569-07-24 500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 107  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0665569000717\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23\",\"province_ja\":\"\u30d4\u30c1\u30c3\u30c8\u770c\",\"search_text\":\"0665569000717 \u0e1a\u0e08.\u0e40\u0e2d\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 244\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e34\u0e08\u0e34\u0e15\u0e23 \u30d4\u30c1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0705569003367\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e01\u0e0b\u0e14\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27\u0e40\u0e23\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003367 \u0e1a\u0e08.\u0e22\u0e01\u0e0b\u0e14\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27\u0e40\u0e23\u0e37\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 167\/16  \u0e16\u0e19\u0e19\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e01\u0e38\u0e25 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002212\",\"name_th\":\"\u0e1a\u0e08.\u0e2d.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002212 \u0e1a\u0e08.\u0e2d.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e0a\u0e31\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d - \u0e02\u0e32\u0e22 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569003111\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003111 \u0e1a\u0e08.\u0e2d\u0e2d\u0e19\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e2a\u0e39\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/32  \u0e16\u0e19\u0e19\u0e0a\u0e21\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002891\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e04\u0e23 \u0e40\u0e27\u0e47\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e19\u0e32\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002891 \u0e1a\u0e08.\u0e19\u0e04\u0e23 \u0e40\u0e27\u0e47\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e19\u0e32\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e42\u0e14\u0e22\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 39\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0825569001185\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e2b\u0e25\u0e31\u0e01 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32\",\"province_ja\":\"\u30d1\u30f3\u30ac\u30fc\u770c\",\"search_text\":\"0825569001185 \u0e1a\u0e08.\u0e40\u0e02\u0e32\u0e2b\u0e25\u0e31\u0e01 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e08\u0e14\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e27\u0e35\u0e0b\u0e48\u0e32 (visa) \u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 (work permit) \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 64\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e31\u0e07\u0e07\u0e32 \u30d1\u30f3\u30ac\u30fc\u770c\"},{\"reg_no\":\"0835569013671\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e38\u0e22\u0e2a\u0e4c \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013671 \u0e1a\u0e08.\u0e2b\u0e25\u0e38\u0e22\u0e2a\u0e4c \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e47\u0e2d\u0e1f\u0e1f\u0e35\u0e48\u0e0a\u0e47\u0e2d\u0e1b \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e19\u0e31\u0e48\u0e07\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e2a\u0e31\u0e48\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48 (\u0e40\u0e14\u0e25\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48) \u5bbf\u6cca\u30fb\u98f2\u98df 74\/51  \u0e16\u0e19\u0e19\u0e19\u0e32\u0e43\u0e19 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0903569001760\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e1e\u0e35 \u0e41\u0e2d\u0e23\u0e4c  \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001760 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04\u0e1e\u0e35 \u0e41\u0e2d\u0e23\u0e4c  \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-24 500000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/19  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e02\u0e27\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006178\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e34\u0e27\u0e14\u0e36\u0e01\u0e04\u0e36\u0e01\u0e1a\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006178 \u0e1a\u0e08.\u0e2b\u0e34\u0e27\u0e14\u0e36\u0e01\u0e04\u0e36\u0e01\u0e1a\u0e48\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 (delivery) \u5bbf\u6cca\u30fb\u98f2\u98df 61  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006216\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e17\u0e39\u0e04\u0e31\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006216 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e17\u0e39\u0e04\u0e31\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e01\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 36  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e2d\u0e40\u0e23\u0e35\u0e22 36 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e08\u0e34\u0e01-\u0e23\u0e32\u0e21\u0e31\u0e0d \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0935569000871\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e19\u0e40\u0e2d\u0e19\u0e1e\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000871 \u0e1a\u0e08.\u0e40\u0e2d\u0e19\u0e40\u0e2d\u0e19\u0e1e\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0965569000579\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e25\u0e34 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0965569000579 \u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e25\u0e34 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 500000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 19  \u0e0b\u0e2d\u0e22 \u0e0a\u0e49\u0e32\u0e07 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\u0e44\u0e0a\u0e22\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569007927\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007927 \u0e2b\u0e08.\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-23 500000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e39\u0e49\u0e41\u0e0a\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e42\u0e15\u0e40\u0e21\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 620  \u0e0b\u0e2d\u0e22 \u0e19\u0e34\u0e21\u0e34\u0e15\u0e43\u0e2b\u0e21\u0e48 36 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007943\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e39\u0e14\u0e14\u0e35\u0e49\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007943 \u0e2b\u0e08.\u0e01\u0e39\u0e14\u0e14\u0e35\u0e49\u0e41\u0e25\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-23 500000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/524  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 111 \u0e41\u0e22\u0e01 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007951\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e1a\u0e39\u0e01\u0e32\u0e21\u0e35\u0e40\u0e25\u0e35\u0e22\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007951 \u0e2b\u0e08.\u0e2d\u0e1a\u0e39\u0e01\u0e32\u0e21\u0e35\u0e40\u0e25\u0e35\u0e22 2569-07-23 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e0a\u0e32\u0e22\u0e21\u0e38\u0e2a\u0e25\u0e34\u0e21 \u0e1c\u0e49\u0e32\u0e42\u0e1e\u0e01\u0e28\u0e23\u0e35\u0e29\u0e30 (\u0e2a\u0e32\u0e23\u0e32\u0e1a\u0e31\u0e48\u0e19 \/ turban) \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/1  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007960\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e20\u0e34\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e22\u0e2d\u0e14\u0e17\u0e31\u0e1e \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007960 \u0e2b\u0e08.\u0e2d\u0e20\u0e34\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e22\u0e2d\u0e14\u0e17\u0e31\u0e1e \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-23 500000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 105\/295  \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 29 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138624\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e43\u0e2a\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138624 \u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e43\u0e2a\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 78109 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 48\/875  \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e2241 \u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139027\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e2a\u0e22\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139027 \u0e1a\u0e08.\u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e2a\u0e22\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/2  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 (\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139256\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139256 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 159\/37  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 23 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 21 (\u0e2d\u0e42\u0e28\u0e01) \u0e16\u0e19\u0e19\u0e38\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139426\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e21\u0e34\u0e19\u0e17\u0e32\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139426 \u0e1a\u0e08.\u0e2d\u0e21\u0e34\u0e19\u0e17\u0e32\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e27\u0e25 \u0e40\u0e19\u0e2a \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e32\u0e43\u0e0a\u0e49\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e42\u0e20\u0e0a\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 9\/52  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e0b\u0e2d\u0e22 1 \u0e41\u0e22\u0e01 3-4 \u0e21.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024360\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19 \u0e2a\u0e40\u0e01\u0e25 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024360 \u0e1a\u0e08.\u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19 \u0e2a\u0e40\u0e01\u0e25 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e1a\u0e34\u0e25\u0e17\u0e4c\u0e2d\u0e34\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 592\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569038556\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e42\u0e1b\u0e23 \u0e44\u0e21\u0e19\u0e34\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038556 \u0e1a\u0e08.\u0e17\u0e35 \u0e42\u0e1b\u0e23 \u0e44\u0e21\u0e19\u0e34\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038734\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038734 \u0e1a\u0e08.\u0e1e\u0e35\u0e1a\u0e35 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e40\u0e17\u0e1b\u0e19\u0e32\u0e42\u0e19\u0e15\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e01\u0e31\u0e19\u0e2a\u0e36\u0e01\u0e2b\u0e23\u0e2d \u0e40\u0e17\u0e1b\u0e01\u0e32\u0e27\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 197\/174  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569004007\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e42\u0e0a\u0e04\u0e28\u0e34\u0e23\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96304\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96304\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004007 \u0e1a\u0e08.\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e42\u0e0a\u0e04\u0e28\u0e34\u0e23\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 96304 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e34\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1a\u0e39\u0e0a\u0e32\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e25\u0e31\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0405569007101\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e0b\u0e31\u0e19 \u0e40\u0e25\u0e34\u0e1f\u0e22\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007101 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35 \u0e0b\u0e31\u0e19 \u0e40\u0e25\u0e34\u0e1f\u0e22\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e04\u0e23\u0e35\u0e21\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e27\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e1c\u0e48\u0e19\u0e21\u0e32\u0e2a\u0e4c\u0e01\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e1c\u0e48\u0e19\u0e21\u0e32\u0e2a\u0e4c\u0e01\u0e14\u0e27\u0e07\u0e15\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27\u0e01\u0e32\u0e22 \u0e2a\u0e1a\u0e39\u0e48 \u0e04\u0e23\u0e35\u0e21\u0e17\u0e32\u0e1c\u0e34\u0e27 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 579  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569007128\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007128 \u0e1a\u0e08.\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 90002 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e35\u0e14\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u82b8\u8853\u30fb\u5a2f\u697d 777\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0443569000881\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e31\u0e49\u0e21\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"13999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"13999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000881 \u0e2b\u0e08.\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e31\u0e49\u0e21 2569-07-23 500000 13999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e21\u0e38\u0e49\u0e07\u0e04\u0e25\u0e38\u0e21\u0e2a\u0e38\u0e48\u0e21\u0e44\u0e01\u0e48 \u0e21\u0e38\u0e49\u0e07 \u0e15\u0e32\u0e02\u0e48\u0e32\u0e22 \u0e1c\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 93  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0463569000784\",\"name_th\":\"\u0e2b\u0e08.\u0e22\u0e39\u0e07\u0e17\u0e2d\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64925\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64925\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000784 \u0e2b\u0e08.\u0e22\u0e39\u0e07\u0e17\u0e2d\u0e07 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-23 500000 64925 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01 \u0e08\u0e33\u0e19\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 157  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0503569005181\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e49\u0e2d\u0e19\u0e17\u0e2d\u0e07\u0e42\u0e20\u0e0a\u0e19\u0e32\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005181 \u0e2b\u0e08.\u0e0a\u0e49\u0e2d\u0e19\u0e17\u0e2d\u0e07\u0e42\u0e20\u0e0a\u0e19\u0e32 2569-07-23 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e38\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e25\u0e32\u0e07\u0e27\u0e31\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 243  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001714\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e17\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10779\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10779\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001714 \u0e1a\u0e08.\u0e40\u0e08 \u0e17\u0e35 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 10779 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u88fd\u9020 41  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e22\u0e25\u0e32\u0e19\u0e19\u0e32 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004811\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e10\u0e1e\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004811 \u0e1a\u0e08.\u0e1b\u0e10\u0e1e\u0e35 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0745569007842\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e1f\u0e39\u0e49\u0e14\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10629\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10629\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007842 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21 \u0e1f\u0e39\u0e49\u0e14\u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 10629 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e0b\u0e23\u0e31\u0e1b\u0e19\u0e49\u0e33\u0e2b\u0e27\u0e32\u0e19\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a  \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1a\u0e23\u0e23\u0e08\u0e38  \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e15\u0e34\u0e14\u0e09\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u88fd\u9020 22\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0805569002866\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e0b\u0e47\u0e2d\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002866 \u0e1a\u0e08.\u0e42\u0e23\u0e25\u0e25\u0e34\u0e48\u0e07 \u0e0b\u0e47\u0e2d\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e25\u0e30\u0e04\u0e23 \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e2a\u0e32\u0e23\u0e04\u0e14\u0e35 \u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e2d\u0e27\u0e35\u0e14\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e16\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u60c5\u5831\u901a\u4fe1\u30fbit 72\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0905569006071\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006071 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 500000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e21\u0e32\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 91\/39  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e08\u0e38\u0e44\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c\u0e23\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569137890\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2a\u0e38\u0e02\u0e25\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137890 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2a\u0e38\u0e02\u0e25\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 47640 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01 (\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e15\u0e38\u0e4a\u0e01\u0e15\u0e32 \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e1e\u0e27\u0e07\u0e01\u0e38\u0e0d\u0e41\u0e08) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 59 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137938\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e14\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137938 \u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e14\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e23\u0e49\u0e32\u0e19\u0e1a\u0e30\u0e2b\u0e21\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e21\u0e39\u0e41\u0e14\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e49\u0e32\u0e27\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e2d\u0e1a \u0e23\u0e49\u0e32\u0e19\u0e02\u0e49\u0e32\u0e27\u0e21\u0e31\u0e19\u0e44\u0e01\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e32\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 (delivery) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 834  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 46 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138136\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e19\u0e19\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138136 \u0e1a\u0e08.\u0e44\u0e19\u0e19\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 535  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 71 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138284\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25 \u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138284 \u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e1a\u0e34\u0e25 \u0e04\u0e23\u0e32\u0e27\u0e19\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 120\/168  \u0e0b\u0e2d\u0e22 \u0e27\u0e0a\u0e34\u0e23\u0e18\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e18\u0e34\u0e15 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024301\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e22\u0e47\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e38\u0e02 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55901\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55901\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024301 \u0e1a\u0e08.\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e22\u0e47\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e38\u0e02 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 55901 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e32\u0e22\u0e1b\u0e35 \u5bbf\u6cca\u30fb\u98f2\u98df 201\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027598\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027598 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e02\u0e19\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e1b\u0e25\u0e32\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/218  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027636\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e47\u0e19. \u0e42\u0e2e\u0e21 2009 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027636 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e47\u0e19. \u0e42\u0e2e\u0e21 2009 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u5efa\u8a2d 36\/99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e1a\u0e34\u0e14 1689 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46431\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46431\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022561 \u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c\u0e17\u0e35 \u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e1a\u0e34\u0e14 1689 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 46431 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 72\/123  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e04\u0e25\u0e2d\u0e07 2 \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 54 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022634\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e19\u0e18\u0e19\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022634 \u0e1a\u0e08.\u0e01\u0e32\u0e19\u0e18\u0e19\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 2\/77  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e0134\/1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0203569003220\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e27\u0e25\u0e39\u0e19\u0e48\u0e32 \u0e1a\u0e39\u0e15\u0e34\u0e04\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003220 \u0e2b\u0e08.\u0e40\u0e27\u0e25\u0e39\u0e19\u0e48\u0e32 \u0e1a\u0e39\u0e15\u0e34\u0e04 2569-07-22 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038408\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e34\u0e25\u0e25\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038408 \u0e1a\u0e08.\u0e04\u0e34\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e23\u0e34\u0e25\u0e25\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e40\u0e15\u0e47\u0e01 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 8\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009777\",\"name_th\":\"\u0e1a\u0e08.\u0e0c\u0e32-\u0e18\u0e32\u0e21 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009777 \u0e1a\u0e08.\u0e0c\u0e32-\u0e18\u0e32\u0e21 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c shopee tiktok lazada \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0243569000735\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e34\u0e1a\u0e31\u0e1a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56299\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56299\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000735 \u0e2b\u0e08.\u0e0a\u0e34\u0e1a\u0e31\u0e1a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 2569-07-22 500000 56299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 451  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0333569000700\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e38\u0e13\u0e28\u0e34\u0e25\u0e32 888\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000700 \u0e2b\u0e08.\u0e1b\u0e38\u0e13\u0e28\u0e34\u0e25\u0e32 888 2569-07-22 500000 43120 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e02\u0e38\u0e14\u0e15\u0e2d\u0e44\u0e21\u0e49 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e14\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u5efa\u8a2d 106  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0373569000254\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e42\u0e04\u0e27\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"13132\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"13132\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0373569000254 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e42\u0e04\u0e27 2569-07-22 500000 13132 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e31\u0e48\u0e19\u0e14\u0e49\u0e32\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e2d\u0e1c\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e22\u0e49\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e1c\u0e49\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e2a\u0e2d\u0e1a \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e31\u0e14\u0e1b\u0e2d \u88fd\u9020 393-393\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005114\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e34\u0e4a\u0e01 \u0e23\u0e16\u0e02\u0e38\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005114 \u0e2b\u0e08.\u0e15\u0e34\u0e4a\u0e01 \u0e23\u0e16\u0e02\u0e38\u0e14 2569-07-22 500000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e16\u0e2b\u0e01\u0e25\u0e49\u0e2d \u0e23\u0e16\u0e41\u0e21\u0e47\u0e04\u0e42\u0e04\u0e23 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e25\u0e32\u0e01  \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 132  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016487\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04\u0e23 \u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016487 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e04\u0e23 \u0e27\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01 \u0e2d\u0e1a \u0e23\u0e35\u0e14 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e1a\u0e1c\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 786  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016525\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e43\u0e08\u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016525 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e43\u0e08\u0e40\u0e17\u0e23\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 82301 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e17\u0e31\u0e01\u0e29\u0e30\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e01\u0e15\u0e34 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0603569001665\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e20\u0e34 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001665 \u0e2b\u0e08.\u0e2d\u0e20\u0e34 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c 2569-07-22 500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0653569001185\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2d.\u0e40\u0e2d. \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001185 \u0e2b\u0e08.\u0e42\u0e2d.\u0e40\u0e2d. \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 2569-07-22 500000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 43\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0655569002361\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e14\u0e1b\u0e31\u0e01\u0e01\u0e34\u0e48\u0e07\u0e40\u0e0a\u0e1f\u0e18\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002361 \u0e1a\u0e08.\u0e40\u0e1b\u0e47\u0e14\u0e1b\u0e31\u0e01\u0e01\u0e34\u0e48\u0e07\u0e40\u0e0a\u0e1f\u0e18\u0e19\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e42\u0e15\u0e4a\u0e30\u0e08\u0e35\u0e19  \u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2f\u0e25\u0e2f \u5bbf\u6cca\u30fb\u98f2\u98df 303\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0713569000552\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0713569000552 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 2569-07-22 500000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16  \u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e04 \u0e1b\u0e30\u0e1c\u0e38 \u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e25\u0e49\u0e32\u0e07 \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 265  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007443\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e0a \u0e27\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16230\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16230\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007443 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e0a \u0e27\u0e39\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 16230 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e44\u0e21\u0e49\u0e43\u0e0a\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 14\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0845569010761\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010761 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e1b\u0e32\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 500000 46202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e1c\u0e25\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e17\u0e30\u0e25\u0e32\u0e22 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e23\u0e48\u0e27\u0e07 \u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/84  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1e\u0e48\u0e2d\u0e02\u0e38\u0e19\u0e17\u0e30\u0e40\u0e25 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569137105\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e13\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c   \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137105 \u0e1a\u0e08.\u0e21\u0e13\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c   \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e25\u0e39\u0e01\u0e1b\u0e31\u0e14 \u0e2b\u0e34\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e2b\u0e34\u0e19\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32\/5  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c 15\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137164\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35. \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137164 \u0e1a\u0e08.\u0e1e\u0e35.\u0e17\u0e35. \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 269\/261  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e22\u0e32\u0e2a\u0e38\u0e40\u0e23\u0e19\u0e17\u0e23\u0e4c 30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137385\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e08\u0e19\u0e14\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14115\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14115\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137385 \u0e1a\u0e08.\u0e40\u0e25\u0e40\u0e08\u0e19\u0e14\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 14115 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e04\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e35\u0e2c\u0e32 \u88fd\u9020 93,95  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 26 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0123569002259\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e32\u0e25\u0e27\u0e31\u0e0f \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002259 \u0e2b\u0e08.\u0e01\u0e32\u0e25\u0e27\u0e31\u0e0f \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 2569-07-21 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e0b\u0e37\u0e49\u0e2d\u0e42\u0e14\u0e22\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e08\u0e32\u0e01\u0e42\u0e06\u0e29\u0e13\u0e32\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e42\u0e14\u0e22\u0e1b\u0e01\u0e15\u0e34\u0e08\u0e30\u0e1c\u0e48\u0e32\u0e19 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e08\u0e30\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e08\u0e17\u0e4d\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e2a\u0e39\u0e1a \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e4d\u0e32\u0e2d\u0e32\u0e07 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 198\/226  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002569\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e1f\u0e23\u0e0a\u0e21\u0e32\u0e23\u0e4c\u0e17\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47113\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47113\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002569 \u0e2b\u0e08.\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e1f\u0e23\u0e0a\u0e21\u0e32\u0e23\u0e4c\u0e17 2569-07-21 500000 47113 \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e0b\u0e37\u0e49\u0e2d\/\u0e21\u0e34\u0e19\u0e34\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e40\u0e1f\u0e23\u0e19\u0e44\u0e0a\u0e2a\u0e4c\u0e21\u0e34\u0e19\u0e34\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e0a\u0e33 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e2d\u0e37\u0e48\u0e19 \u0e46  \u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e14\u0e34\u0e2a\u0e40\u0e04\u0e49\u0e32\u0e17\u0e4c\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0305569007552\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e33\u0e44\u0e23\u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007552 \u0e1a\u0e08.\u0e01\u0e33\u0e44\u0e23\u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0313569001102\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19  \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2026\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001102 \u0e2b\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19  \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2026 2569-07-21 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c  \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25  \u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 - \u0e43\u0e2b\u0e0d\u0e48 \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 251  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0343569001994\",\"name_th\":\"\u0e2b\u0e08.\u0e2d.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001994 \u0e2b\u0e08.\u0e2d.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-21 500000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e16\u0e41\u0e17\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e16\u0e02\u0e38\u0e14\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19\u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e01\u0e48\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e43\u0e2b\u0e21\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003858\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e42\u0e1f\u0e25\u0e27\u0e4c 2028 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01301\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01301\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003858 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e42\u0e1f\u0e25\u0e27\u0e4c 2028 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 01301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e1e\u0e32\u0e30\u0e0a\u0e33 \u0e40\u0e1e\u0e32\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u0e01\u0e25\u0e49\u0e32\u0e44\u0e21\u0e49 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e44\u0e21\u0e49\u0e14\u0e2d\u0e01 \u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e44\u0e21\u0e49\u0e22\u0e37\u0e19\u0e15\u0e49\u0e19 \u0e44\u0e21\u0e49\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 279  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016401\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016401 \u0e1a\u0e08.\u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell)  \u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 463  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001455\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001455 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e04\u0e34\u0e17\u0e40\u0e0a\u0e48\u0e19\u0e1f\u0e39\u0e4a\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002247\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002247 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c 2569-07-21 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 410\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0745569007702\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e48\u0e32 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007702 \u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e48\u0e32 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 46694 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e27\u0e14\u0e41\u0e01\u0e49\u0e27 \u0e02\u0e27\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e04 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1d\u0e32\u0e1b\u0e31\u0e49\u0e21\u0e41\u0e25\u0e30\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0845569010613\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010613 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0925569001109\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e35 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001109 \u0e1a\u0e08.\u0e01\u0e33\u0e25\u0e31\u0e07\u0e14\u0e35 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e44\u0e21\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 500000 46632 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32  \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e21\u0e49\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e44\u0e21\u0e49\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07\u0e41\u0e25\u0e30\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49\u0e17\u0e38\u0e1b\u0e01\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0103569007773\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d \u0e08\u0e35 \u0e44\u0e2d \u0e2d\u0e35\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007773 \u0e2b\u0e08.\u0e44\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2d \u0e08\u0e35 \u0e44\u0e2d \u0e2d\u0e35 2569-07-20 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 [\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19] \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 24 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136257\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e14\u0e34\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136257 \u0e1a\u0e08.\u0e2d\u0e14\u0e34\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 69200 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25\/3  \u0e0b\u0e2d\u0e22 \u0e28\u0e32\u0e25\u0e32\u0e25\u0e2d\u0e22 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 71 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136371\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e40\u0e04\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136371 \u0e1a\u0e08.\u0e14\u0e35\u0e1e\u0e35\u0e22\u0e39\u0e40\u0e04\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e42\u0e23\u0e07\u0e22\u0e34\u0e21 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e2a\u0e19\u0e32\u0e21\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e17\u0e40\u0e17\u0e34\u0e25\u0e1a\u0e2d\u0e25 (kettlebell) \u0e41\u0e25\u0e30\u0e01\u0e35\u0e2c\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u82b8\u8853\u30fb\u5a2f\u697d 16\/178  \u0e0b\u0e2d\u0e22 \u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 58 \u0e41\u0e22\u0e01 1-2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136656\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136656 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 93111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19 \u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e35\u0e2c\u0e32\u0e40\u0e17\u0e19\u0e19\u0e34\u0e2a\u0e41\u0e01\u0e48\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e32\u0e22\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e04\u0e48\u0e32\u0e22\u0e01\u0e35\u0e2c\u0e32 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u82b8\u8853\u30fb\u5a2f\u697d 178\/70  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e40\u0e1e\u0e25\u0e2a \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 62 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 62 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136737\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136737 \u0e1a\u0e08.\u0e40\u0e08\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 47219 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35 \u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 271\/20  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e18\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002585\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e1a\u0e39\u0e15\u0e34\u0e01\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002585 \u0e2b\u0e08.\u0e40\u0e04\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e1a\u0e39\u0e15\u0e34\u0e01 2569-07-20 500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7,9  \u0e0b\u0e2d\u0e22 1 (\u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e25\u0e27\u0e14 ) \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e25\u0e27\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569022391\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e2d\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022391 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e2a\u0e2d\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 43210 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 19\/409  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569009611\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e07\u0e14\u0e49\u0e32 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009611 \u0e1a\u0e08.\u0e17\u0e07\u0e14\u0e49\u0e32 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19 (labour outsourcing) \u904b\u8f38\u30fb\u7269\u6d41 189\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0243569000719\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e0b\u0e35 1968\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"19201\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"19201\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000719 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e0b\u0e35 1968 2569-07-20 500000 19201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e17\u0e32\u0e41\u0e1a\u0e1a \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e08\u0e32\u0e23\u0e30\u0e1a\u0e35 \u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 112\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0243569000727\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35 1981\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"19201\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"19201\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000727 \u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35 1981 2569-07-20 500000 19201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e17\u0e32\u0e41\u0e1a\u0e1a \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e08\u0e32\u0e23\u0e30\u0e1a\u0e35 \u0e2a\u0e32\u0e23\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 152\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0255569002080\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e19\u0e07\u0e19\u0e38\u0e0a - \u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569002080 \u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e19\u0e07\u0e19\u0e38\u0e0a - \u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 81300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e02\u0e32\u0e22\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 391  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007471\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e16\u0e40\u0e2e\u0e35\u0e4a\u0e22\u0e1a\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007471 \u0e1a\u0e08.\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e16\u0e40\u0e2e\u0e35\u0e4a\u0e22\u0e1a\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 77109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e16\u0e40\u0e04\u0e23\u0e19 \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e15\u0e34\u0e14\u0e40\u0e04\u0e23\u0e19 (\u0e23\u0e16\u0e40\u0e2e\u0e35\u0e4a\u0e22\u0e1a) \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e40\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0305569007498\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e1b\u0e1b\u0e2d\u0e19 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007498 \u0e1a\u0e08.\u0e19\u0e34\u0e1b\u0e1b\u0e2d\u0e19 \u0e42\u0e21\u0e25\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 18121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e21\u0e48\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0385569000515\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35 \u0e42\u0e19 \u0e25\u0e34\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45303\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45303\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000515 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35 \u0e42\u0e19 \u0e25\u0e34\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 45303 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e02\u0e32\u0e22\u0e42\u0e14\u0e22\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e34\u0e18\u0e35\u0e43\u0e14\u0e01\u0e47\u0e15\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 154  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003236\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003236 \u0e2b\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c 2569-07-20 500000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0455569001529\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001529 \u0e1a\u0e08.\u0e40\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e08 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e41\u0e17\u0e48\u0e07\u0e41\u0e25\u0e30\u0e17\u0e2d\u0e07\u0e04\u0e33\u0e23\u0e39\u0e1b\u0e1e\u0e23\u0e23\u0e13 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e1c\u0e48\u0e2d\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 269  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0505569016282\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e44\u0e2d. \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016282 \u0e1a\u0e08.\u0e1e\u0e35.\u0e44\u0e2d. \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u5efa\u8a2d 98\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016347\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e23\u0e19 \u0e41\u0e2d\u0e25\u0e40\u0e25\u0e48\u0e40\u0e1f\u0e48\u0e19 \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016347 \u0e1a\u0e08.\u0e04\u0e32\u0e40\u0e23\u0e19 \u0e41\u0e2d\u0e25\u0e40\u0e25\u0e48\u0e40\u0e1f\u0e48\u0e19 \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1e\u0e32\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e1b\u0e14\u0e39\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e0a\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e19\u0e1b\u0e48\u0e32 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0a\u0e49\u0e32\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 308\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e2b\u0e49\u0e27\u0e22\u0e2a\u0e49\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0545569000823\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e2d\u0e25\u0e59\u0e59\u0e59 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000823 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e2d\u0e2d\u0e25\u0e59\u0e59\u0e59 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0633569000758\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e40\u0e23\u0e28 \u0e17\u0e48\u0e2d\u0e44\u0e2d\u0e40\u0e2a\u0e35\u0e22\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000758 \u0e2b\u0e08.\u0e19\u0e40\u0e23\u0e28 \u0e17\u0e48\u0e2d\u0e44\u0e2d\u0e40\u0e2a\u0e35\u0e22 2569-07-20 500000 29309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e17\u0e48\u0e2d\u0e44\u0e2d\u0e40\u0e2a\u0e35\u0e22 \u0e01\u0e31\u0e19\u0e0a\u0e19\u0e43\u0e1a\u0e21\u0e35\u0e14 \u0e04\u0e2d\u0e01\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e01\u0e31\u0e19\u0e0a\u0e19 \u0e42\u0e23\u0e1a\u0e32\u0e23\u0e4c \u0e1a\u0e31\u0e19\u0e44\u0e14\u0e02\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e1f\u0e42\u0e23\u0e14 \u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 104\/2  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e40\u0e2d\u0e40\u0e0b\u0e35\u0e22 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0633569000766\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e38\u0e4a\u0e01\u0e01\u0e35\u0e49\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e42\u0e21\u0e1a\u0e32\u0e22\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000766 \u0e2b\u0e08.\u0e15\u0e38\u0e4a\u0e01\u0e01\u0e35\u0e49\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e42\u0e21\u0e1a\u0e32\u0e22 2569-07-20 500000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e0b\u0e34\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 155\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0735569007397\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e04\u0e23\u0e39\u0e27\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007397 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e04\u0e23\u0e39\u0e27\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23  \u0e41\u0e25\u0e30\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e40\u0e0a\u0e34\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e43\u0e19\u0e07\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 (event consultant & marketing) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 59\/64  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0905569005945\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e32\u0e15\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005945 \u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e32\u0e15\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 224  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1a\u0e36\u0e07\u0e1e\u0e34\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0915569000366\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e21 \u0e1a. \u0e02\u0e27\u0e31\u0e0d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0915569000366 \u0e1a\u0e08.\u0e2a\u0e32\u0e21 \u0e1a. \u0e02\u0e27\u0e31\u0e0d\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e25\u0e48\u0e32 \u4e0d\u52d5\u7523 142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0945569000749\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e40\u0e25\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e0a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000749 \u0e1a\u0e08.\u0e41\u0e1a\u0e25\u0e47\u0e04 \u0e40\u0e25\u0e40\u0e22\u0e2d\u0e23\u0e4c \u0e0a\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e27\u0e34\u0e19\u0e40\u0e17\u0e08\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/117  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569136028\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e2d\u0e17 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136028 \u0e1a\u0e08.\u0e18\u0e2d\u0e17 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 208  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e34\u0e23\u0e31\u0e19\u0e14\u0e23\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 2 \u0e0b\u0e2d\u0e22 23 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027237\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46694\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46694\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027237 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 500000 46694 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e1e\u0e47\u0e04\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/138  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0405569006962\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e01\u0e04\u0e39\u0e13\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006962 \u0e1a\u0e08.\u0e14\u0e2d\u0e01\u0e04\u0e39\u0e13\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 500000 47114 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e32\u0e19\u0e42\u0e0a\u0e2b\u0e48\u0e27\u0e22\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e32\u0e21\u0e15\u0e23\u0e2d\u0e01 \u0e0b\u0e2d\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e02\u0e49\u0e32\u0e27 \u0e41\u0e1b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0715569002727\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e40\u0e04 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002727 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35\u0e40\u0e04 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 121\/135  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569135820\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135820 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e14 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e19\u0e27\u0e48\u0e32\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/74  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e08\u0e2d\u0e21\u0e17\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135846\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135846 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d \u0e1f\u0e39\u0e49\u0e14 \u0e01\u0e23\u0e38\u0e4a\u0e1b  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 (catering) \u5bbf\u6cca\u30fb\u98f2\u98df 54\/85  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 16 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135927\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135927 \u0e1a\u0e08.\u0e1a\u0e35\u0e27\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 97  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002577\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e07\u0e04\u0e25 4289\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002577 \u0e2b\u0e08.\u0e21\u0e07\u0e04\u0e25 4289 2569-07-18 500000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c ( \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 ) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299\/332  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023797\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43309\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43309\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023797 \u0e1a\u0e08.\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e34\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 43309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5efa\u8a2d 909\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027181\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e25\u0e32\u0e25\u0e34\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027181 \u0e1a\u0e08.\u0e40\u0e21\u0e25\u0e32\u0e25\u0e34\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/159  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 (\u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022171\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e2a\u0e0b\u0e34\u0e42\u0e2d\u0e40\u0e19\u0e48 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022171 \u0e1a\u0e08.\u0e1e\u0e32\u0e2a\u0e0b\u0e34\u0e42\u0e2d\u0e40\u0e19\u0e48 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1493  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569037801\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e07\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037801 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21 \u0e04\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e07\u0e2a\u0e4c (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 344\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0473569000971\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e01\u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e482489\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000971 \u0e2b\u0e08.\u0e23\u0e31\u0e01\u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e482489 2569-07-18 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004641\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 159 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47741\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47741\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004641 \u0e1a\u0e08.\u0e14\u0e27\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35 159 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 47741 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e39\u0e0a\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e02\u0e25\u0e31\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0615569000598\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e15\u0e19\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000598 \u0e1a\u0e08.\u0e08\u0e34\u0e19\u0e15\u0e19\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 47114 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e41\u0e1a\u0e1a\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e49\u0e32\u0e19\u0e42\u0e0a\u0e2b\u0e48\u0e27\u0e22\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e32\u0e21\u0e15\u0e23\u0e2d\u0e01 \u0e0b\u0e2d\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e02\u0e49\u0e32\u0e27 \u0e41\u0e1b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0745569007605\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e04\u0e31\u0e1f\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007605 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e04\u0e31\u0e1f\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 206\/17\u0e04  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e29\u0e0e\u0e32\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569005899\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e38\u0e48\u0e19\u0e19\u0e49\u0e33 \u0e23\u0e34\u0e0a \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005899 \u0e1a\u0e08.\u0e19\u0e38\u0e48\u0e19\u0e19\u0e49\u0e33 \u0e23\u0e34\u0e0a \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 500000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 63\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569135013\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25 \u0e41\u0e21\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135013 \u0e1a\u0e08.\u0e42\u0e0b\u0e25 \u0e41\u0e21\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e25\u0e30\u0e04\u0e23\u0e40\u0e27\u0e17\u0e35 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35 \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e1a\u0e39\u0e18 \u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e2a\u0e14\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e25\u0e30\u0e04\u0e23 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d \u0e02\u0e32\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u82b8\u8853\u30fb\u5a2f\u697d 222\/77  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e2a\u0e32\u0e17\u0e23 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135307\",\"name_th\":\"\u0e1a\u0e08.\u0e10\u0e32\u0e19\u0e34\u0e0d\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135307 \u0e1a\u0e08.\u0e10\u0e32\u0e19\u0e34\u0e0d\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e1e\u0e23\u0e21 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023720\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e35\u0e44\u0e2d \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023720 \u0e1a\u0e08.\u0e40\u0e2d\u0e27\u0e35\u0e44\u0e2d \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 (erp) \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c (crm) \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 3592  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027024\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0c\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027024 \u0e1a\u0e08.\u0e40\u0e0c\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01 \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e1c\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c  \u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e31\u0e13\u0e11\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 19\/75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027067\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e14\u0e35 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027067 \u0e1a\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e2a\u0e0b\u0e35\u0e14\u0e35 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e14\u0e47\u0e01\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u533b\u7642\u30fb\u798f\u7949 112\/134  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 16 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e28\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021999\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34 \u0e14\u0e34\u0e40\u0e1f\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021999 \u0e1a\u0e08.\u0e27\u0e34 \u0e14\u0e34\u0e40\u0e1f\u0e19\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e44\u0e1b\u0e0b\u0e37\u0e49\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e19\u0e31\u0e49\u0e19\u0e46 \u91d1\u878d\u30fb\u4fdd\u967a 98\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0193569000795\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e31\u0e19\u0e18\u0e27\u0e31\u0e0a 2026\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000795 \u0e2b\u0e08.\u0e1e\u0e31\u0e19\u0e18\u0e27\u0e31\u0e0a 2026 2569-07-17 500000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003131\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003131 \u0e2b\u0e08.\u0e27\u0e32\u0e2a\u0e19\u0e32 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 2569-07-17 500000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 699\/20-21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003149\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e1b\u0e23 \u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003149 \u0e2b\u0e08.\u0e42\u0e1b\u0e23 \u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e40\u0e21\u0e19\u0e40\u0e17\u0e19\u0e41\u0e19\u0e19\u0e0b\u0e4c 2569-07-17 500000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009548\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e04\u0e27\u0e35 \u0e1e\u0e34\u0e01\u0e40\u0e0b\u0e25 1998 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59122\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59122\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009548 \u0e1a\u0e08. \u0e40\u0e04\u0e27\u0e35 \u0e1e\u0e34\u0e01\u0e40\u0e0b\u0e25 1998 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 59122 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01 (graphic design), \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (logo), \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c (packaging)  \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u60c5\u5831\u901a\u4fe1\u30fbit 457\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0315569001937\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e35 159 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001937 \u0e1a\u0e08.\u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e21 \u0e1a\u0e35 159 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 314  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0363569000939\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e14\u0e35 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 1988\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000939 \u0e2b\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e14\u0e35 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 1988 2569-07-17 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 175  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0403569003228\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e42\u0e08\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003228 \u0e2b\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e42\u0e08\u0e23 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-17 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 788\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003742\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e32\u0e27\u0e38\u0e12\u0e34 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003742 \u0e1a\u0e08.\u0e08\u0e31\u0e01\u0e23\u0e32\u0e27\u0e38\u0e12\u0e34 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 206\/23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016169\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016169 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e40\u0e1e\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (innovation holding & platform company) \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a 1.\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 2.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32 3.\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 4.\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c 5.\u0e2a\u0e39\u0e15\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e21\u0e48 6.\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c 7.\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 8.\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e43\u0e2b\u0e21\u0e48 9.\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 (trademark) 10.\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c (software) 11.\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (database) 12.\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 (technology platform) 13.\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c (product design) 14.\u0e01\u0e23\u0e2d\u0e1a\u0e07\u0e32\u0e19\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c (commercial framework) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 234\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004624\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e34\u0e15\u0e15\u0e4c\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93199\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93199\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004624 \u0e1a\u0e08.\u0e2a\u0e27\u0e34\u0e15\u0e15\u0e4c\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 93199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e22\u0e34\u0e07\u0e1b\u0e37\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21 \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u82b8\u8853\u30fb\u5a2f\u697d 450\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0583569000139\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e34\u0e01\u0e02\u0e4c\u0e19\u0e34\u0e20\u0e32 \u0e19\u0e34\u0e22\u0e21\u0e1e\u0e32\u0e19\u0e34\u0e0a\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\",\"province_ja\":\"\u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\",\"search_text\":\"0583569000139 \u0e2b\u0e08.\u0e19\u0e34\u0e01\u0e02\u0e4c\u0e19\u0e34\u0e20\u0e32 \u0e19\u0e34\u0e22\u0e21\u0e1e\u0e32\u0e19\u0e34\u0e0a 2569-07-17 500000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 240\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0633569000740\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e25\u0e2a \u0e40\u0e0b\u0e42\u0e1a\u0e49 \u0e04\u0e25\u0e31\u0e1a\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000740 \u0e2b\u0e08.\u0e40\u0e1e\u0e25\u0e2a \u0e40\u0e0b\u0e42\u0e1a\u0e49 \u0e04\u0e25\u0e31\u0e1a 2569-07-17 500000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e2b\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/84  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e30 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0645569000750\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e01\u0e15\u0e4c\u0e0a\u0e49\u0e2d\u0e22\u0e2a\u0e4c 1995 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000750 \u0e1a\u0e08.\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e01\u0e15\u0e4c\u0e0a\u0e49\u0e2d\u0e22\u0e2a\u0e4c 1995 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b  \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 3\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0735569007257\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e21\u0e14\u0e32\u0e2a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007257 \u0e1a\u0e08.\u0e44\u0e21\u0e14\u0e32\u0e2a \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/50  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007265\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e25\u0e34\u0e17 1989 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007265 \u0e1a\u0e08.\u0e2d\u0e35\u0e25\u0e34\u0e17 1989 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 158  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007273\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e27\u0e19\u0e15\u0e23\u0e32 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007273 \u0e1a\u0e08.\u0e42\u0e19\u0e40\u0e27\u0e19\u0e15\u0e23\u0e32 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 500000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 14\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0903569001654\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e1e\u0e14\u0e25 \u0e02\u0e19\u0e2a\u0e48\u0e07\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001654 \u0e2b\u0e08.\u0e19\u0e1e\u0e14\u0e25 \u0e02\u0e19\u0e2a\u0e48\u0e07 2569-07-17 500000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 114\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007609\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e39\u0e17\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007609 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e0a\u0e39\u0e17\u0e2d\u0e07\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-16 500000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 130  \u0e0b\u0e2d\u0e22 \u0e1a\u0e36\u0e07\u0e02\u0e27\u0e32\u0e07 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134131\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c\u0e40\u0e1f\u0e25\u0e21 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134131 \u0e1a\u0e08.\u0e17\u0e40\u0e27\u0e19\u0e15\u0e35\u0e49\u0e42\u0e1f\u0e23\u0e4c\u0e40\u0e1f\u0e25\u0e21 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 144\/38  \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134157\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e20\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134157 \u0e1a\u0e08.\u0e42\u0e20\u0e04\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 56101 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21: \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e21\u0e07\u0e04\u0e25 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u5bbf\u6cca\u30fb\u98f2\u98df 599\/42  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c 42 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e2d\u0e14\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134271\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e02\u0e49\u0e32\u0e27\u0e01\u0e34\u0e19\u0e41\u0e01\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134271 \u0e1a\u0e08.\u0e01\u0e34\u0e19\u0e02\u0e49\u0e32\u0e27\u0e01\u0e34\u0e19\u0e41\u0e01\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/1  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 40 (\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e21\u0e34\u0e15\u0e23) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134343\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e34\u0e0a\u0e31\u0e19\u0e19\u0e32\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134343 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e34\u0e0a\u0e31\u0e19\u0e19\u0e32\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 23\/206  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134505\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134505 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 47591 \u0e02\u0e32\u0e22\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e1a\u0e1a \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 127  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e01\u0e29\u0e23\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 25.\u0e14\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 25 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134696\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e0b\u0e0b\u0e48\u0e32 \u0e40\u0e07\u0e34\u0e19\u0e40\u0e22\u0e47\u0e19\u0e40\u0e22\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134696 \u0e1a\u0e08.\u0e1e\u0e34\u0e0b\u0e0b\u0e48\u0e32 \u0e40\u0e07\u0e34\u0e19\u0e40\u0e22\u0e47\u0e19\u0e40\u0e22\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1a\u0e34\u0e01\u0e40\u0e07\u0e34\u0e19\u0e40\u0e01\u0e34\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e08\u0e32\u0e01\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e21\u0e35 \u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a \u0e2d\u0e2d\u0e01 \u0e42\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e25\u0e31\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e21\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e1f\u0e2d\u0e07\u0e0b\u0e34\u0e40\u0e2d\u0e23\u0e4c \u91d1\u878d\u30fb\u4fdd\u967a 68  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e49\u0e32\u0e21\u0e1b\u0e39\u0e41\u0e2d\u0e17\u0e2d\u0e42\u0e28\u0e01  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 105 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 21 (\u0e2d\u0e42\u0e28\u0e01) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134769\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e2a \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46492\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46492\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134769 \u0e1a\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e4c\u0e23\u0e34\u0e2a \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 46492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e1e\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32 \u0e41\u0e25\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/429  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e21.\u0e40\u0e1e\u0e0a\u0e23\u0e21\u0e13\u0e11\u0e25\u0e01\u0e23\u0e35\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023495\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e18\u0e35\u0e19\u0e48\u0e32 \u0e41\u0e2d\u0e04\u0e0a\u0e34\u0e42\u0e2d \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023495 \u0e1a\u0e08.\u0e2d\u0e32\u0e18\u0e35\u0e19\u0e48\u0e32 \u0e41\u0e2d\u0e04\u0e0a\u0e34\u0e42\u0e2d \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b\u0e2d\u0e22 8 \u0e16\u0e19\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023533\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023533 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e04 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e22\u0e37\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32  \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 14\/245  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026826\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e19\u0e1e\u0e2a\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10761\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10761\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026826 \u0e1a\u0e08.\u0e41\u0e19\u0e1e\u0e2a\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 10761 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a \u88fd\u9020 5\/997  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026842\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e44\u0e1e\u0e28\u0e32\u0e25 99 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026842 \u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e44\u0e1e\u0e28\u0e32\u0e25 99 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/721  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026885\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e19\u0e42\u0e1a\u0e27\u0e4c \u0e40\u0e0b\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026885 \u0e1a\u0e08.\u0e40\u0e23\u0e19\u0e42\u0e1a\u0e27\u0e4c \u0e40\u0e0b\u0e47\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/32  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026907\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026907 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021867\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e25\u0e34\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32501\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32501\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021867 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e25\u0e34\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 32501 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u88fd\u9020 41\/204  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e01\u0e2a\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0195569002579\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002579 \u0e1a\u0e08.\u0e44\u0e27\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 49323 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01 \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e07\u0e04\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 161  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e32\u0e07\u0e23\u0e30\u0e01\u0e33 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0275569001130\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e2a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001130 \u0e1a\u0e08.\u0e40\u0e08 \u0e40\u0e2d\u0e2a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 84\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0305569007374\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007374 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e44\u0e2d\u0e17\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 135  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0315569001929\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e1a2\u0e44\u0e25\u0e1f\u0e4c 6395 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001929 \u0e1a\u0e08.\u0e41\u0e25\u0e1a2\u0e44\u0e25\u0e1f\u0e4c 6395 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01-\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0343569001919\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e31\u0e0a\u0e23\u0e30\u0e1e\u0e23\u0e23\u0e13 \u0e23\u0e31\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001919 \u0e2b\u0e08.\u0e27\u0e31\u0e0a\u0e23\u0e30\u0e1e\u0e23\u0e23\u0e13 \u0e23\u0e31\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19 2569-07-16 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 428  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0393569000360\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 89\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000360 \u0e2b\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 89 2569-07-16 500000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 114  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0403569003198\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e1b\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003198 \u0e2b\u0e08.\u0e41\u0e2d\u0e1b\u0e40\u0e17\u0e04 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 2569-07-16 500000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e21\u0e1a\u0e32\u0e22\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 229\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003700\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e23 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003700 \u0e1a\u0e08.\u0e42\u0e01\u0e23 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e04\u0e39\u0e48\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e17\u0e32\u0e07 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2a\u0e14 (live streaming) \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 100\/32  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e0a\u0e22\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e19\u0e15\u0e34 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0473569000946\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000946 \u0e2b\u0e08.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e0a\u0e04\u0e17\u0e27\u0e35 2569-07-16 500000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 133  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0485569000956\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e0b\u0e32\u0e01\u0e341919 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000956 \u0e1a\u0e08.\u0e21\u0e34\u0e0b\u0e32\u0e01\u0e341919 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0653569001134\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001134 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569 2569-07-16 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0835569013183\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013183 \u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 139\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e07 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e30\u0e29\u0e31\u0e15\u0e23\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0843569001361\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e38\u0e44\u0e23 \u0e1d\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001361 \u0e2b\u0e08.\u0e2d\u0e38\u0e44\u0e23 \u0e1d\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 2569-07-16 500000 43301 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e1d\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u5efa\u8a2d 50\/161  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0845569010486\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e17\u0e2d\u0e07\u0e43\u0e1a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010486 \u0e1a\u0e08.\u0e01\u0e34\u0e15\u0e15\u0e34\u0e17\u0e2d\u0e07\u0e43\u0e1a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 13\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569133428\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e14\u0e2a\u0e4c\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133428 \u0e1a\u0e08.\u0e42\u0e2d\u0e14\u0e2a\u0e4c\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 89\/46  \u0e2d\u0e32\u0e04\u0e32\u0e23park origin \u0e1e\u0e0d\u0e32\u0e44\u0e17  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 412 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e1e\u0e0d\u0e32\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133649\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e14\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133649 \u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e14\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (social media) \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c (application) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e04\u0e49\u0e19\u0e2b\u0e32 (search engine) \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e27\u0e32\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 79\/163  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 42 \u0e16\u0e19\u0e19\u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133657\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e19\u0e19\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133657 \u0e1a\u0e08.\u0e1e\u0e34\u0e19\u0e19\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u91d1\u878d\u30fb\u4fdd\u967a 548  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e31\u0e19 \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 s38010 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 38 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134084\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e2a \u0e22\u0e39 \u0e23\u0e27\u0e22 \u0e23\u0e27\u0e22 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134084 \u0e1a\u0e08.\u0e21\u0e34\u0e2a \u0e22\u0e39 \u0e23\u0e27\u0e22 \u0e23\u0e27\u0e22 \u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58\/159  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e37\u0e48\u0e2d\u0e15\u0e23\u0e07 \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 54\/1 \u0e41\u0e22\u0e01 4-43 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023312\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e44\u0e1a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023312 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e2d\u0e35\u0e27\u0e35 \u0e44\u0e1a\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 45401 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 204\/157  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e2b\u0e30\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e1d.13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023428\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e19\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023428 \u0e1a\u0e08.\u0e23\u0e31\u0e19\u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 712  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023436\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023436 \u0e1a\u0e08.\u0e19\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15  \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e21\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 (24) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c) (25) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32  \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e23\u0e48\u0e20\u0e32\u0e1e\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (26) \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e31\u0e14\u0e17\u0e31\u0e28\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e08\u0e2d\u0e07\u0e15\u0e31\u0e4b\u0e27\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e21\u0e31\u0e04\u0e04\u0e38\u0e40\u0e17\u0e28\u0e01\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e2d\u0e07 \u88fd\u9020 1088\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002178\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e18\u0e34\u0e22\u0e32\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002178 \u0e2b\u0e08.\u0e2a\u0e38\u0e18\u0e34\u0e22\u0e32 2569-07-15 500000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e2a\u0e2d\u0e19 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e20\u0e32\u0e27\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33 \u0e1a\u0e38\u0e04\u0e25\u0e34\u0e01\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e21\u0e2d\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e08\u0e34\u0e15\u0e27\u0e34\u0e17\u0e22\u0e32 \u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15 \u6559\u80b2 79\/214  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026672\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2b\u0e07\u0e48\u0e32 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47741\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47741\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026672 \u0e1a\u0e08.\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2b\u0e07\u0e48\u0e32 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 47741 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e33\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e23\u0e39\u0e1b \u0e27\u0e31\u0e15\u0e16\u0e38\u0e42\u0e1a\u0e23\u0e32\u0e13 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 31  \u0e0b\u0e2d\u0e22 \u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 8 \u0e41\u0e22\u0e01 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002461\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e34\u0e0a\u0e0a\u0e4c\u0e40\u0e19\u0e2a\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002461 \u0e2b\u0e08.\u0e23\u0e34\u0e0a\u0e0a\u0e4c\u0e40\u0e19\u0e2a\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c 2569-07-15 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e49\u0e32\u0e19  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 39\/133  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569037339\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037339 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e15\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 44\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037436\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e40\u0e1a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037436 \u0e1a\u0e08.\u0e42\u0e01\u0e40\u0e1a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 8   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 j1-b06-09 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037444\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e14\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037444 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e14\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 8   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 j1-b06-09 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009483\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e24\u0e15 \u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009483 \u0e1a\u0e08.\u0e18\u0e19\u0e01\u0e24\u0e15 \u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 92\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0393569000351\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e49\u0e21.\u0e42\u0e2d \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0393569000351 \u0e2b\u0e08.\u0e2a\u0e49\u0e21.\u0e42\u0e2d \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 2569-07-15 500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0403569003180\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e27\u0e32\u0e40\u0e25\u0e47\u0e15 \u0e21\u0e39\u0e19\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003180 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e27\u0e32\u0e40\u0e25\u0e47\u0e15 \u0e21\u0e39\u0e19 2569-07-15 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 319  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0445569001715\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e23\u0e27\u0e34\u0e28 \u0e04\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49321\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49321\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001715 \u0e1a\u0e08.\u0e2a\u0e23\u0e27\u0e34\u0e28 \u0e04\u0e32\u0e23\u0e4c\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 49321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0505569015944\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e44\u0e2d \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015944 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e44\u0e2d \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e17\u0e33\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 557\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015952\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e21\u0e35\u0e48 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015952 \u0e1a\u0e08.\u0e21\u0e35\u0e21\u0e35\u0e48 \u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000724\",\"name_th\":\"\u0e2b\u0e08.\u0e1c\u0e49\u0e32\u0e1b\u0e48\u0e32\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000724 \u0e2b\u0e08.\u0e1c\u0e49\u0e32\u0e1b\u0e48\u0e32\u0e19\u0e25\u0e49\u0e32\u0e19\u0e19\u0e32 2569-07-15 500000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e0a\u0e38\u0e14\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e1b\u0e48\u0e32\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e42\u0e17\u0e40\u0e23 \u0e0a\u0e38\u0e14\u0e19\u0e27\u0e14\u0e2a\u0e1b\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e41\u0e1a\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 4\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0543569000279\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d.\u0e1e\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52291\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52291\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0543569000279 \u0e2b\u0e08.\u0e40\u0e2d.\u0e1e\u0e35 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-15 500000 52291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e32\u0e07\u0e23\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 93\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0653569001100\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e23\u0e39\u0e0b\u0e31\u0e19\u0e1e\u0e34\u0e14\u0e42\u0e25\u0e01 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001100 \u0e2b\u0e08.\u0e04\u0e23\u0e39\u0e0b\u0e31\u0e19\u0e1e\u0e34\u0e14\u0e42\u0e25\u0e01 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 2569-07-15 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e01\u0e01\u0e23\u0e07\u0e2b\u0e31\u0e27\u0e08\u0e38\u0e01 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e01\u0e01\u0e23\u0e07\u0e2b\u0e31\u0e27\u0e08\u0e38\u0e01  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e0a\u0e48\u0e19 shopee, lazada, tiktok, youtube, facebook , instagram \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0653569001118\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001118 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e2d\u0e07 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-15 500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0735569007125\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e21\u0e31\u0e25\u0e15\u0e34\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47891\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47891\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007125 \u0e1a\u0e08.\u0e40\u0e04 \u0e21\u0e31\u0e25\u0e15\u0e34\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 47891 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e42\u0e1f\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0755569000538\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e39\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0755569000538 \u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e39\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e1c\u0e48\u0e2d\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0903569001646\",\"name_th\":\"\u0e2b\u0e08.\u0e43\u0e19\u0e15\u0e33\u0e19\u0e32\u0e19\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001646 \u0e2b\u0e08.\u0e43\u0e19\u0e15\u0e33\u0e19\u0e32\u0e19 2569-07-15 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4  \u0e0b\u0e2d\u0e22 \u0e0a\u0e37\u0e48\u0e19\u0e2d\u0e38\u0e17\u0e34\u0e28\u0e41\u0e01\u0e49\u0e27\u0e2a\u0e21\u0e34\u0e17\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005759\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005759 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 43210 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u5efa\u8a2d 110\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005783\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66221\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66221\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005783 \u0e1a\u0e08.\u0e21\u0e31\u0e07\u0e01\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e1f\u0e49\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 500000 66221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u91d1\u878d\u30fb\u4fdd\u967a 67  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e22\u0e17\u0e2d\u0e07(\u0e17\u0e38\u0e48\u0e07\u0e40\u0e02\u0e35\u0e22\u0e27\u0e2b\u0e27\u0e32\u0e19) \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0963569000305\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e31\u0e25 \u0e2d\u0e34\u0e1a\u0e23\u0e32\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000305 \u0e2b\u0e08.\u0e2d\u0e31\u0e25 \u0e2d\u0e34\u0e1a\u0e23\u0e32 2569-07-15 500000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e35\u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 136\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569007501\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007501 \u0e2b\u0e08.\u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-14 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 79\/317  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e17\u0e23\u0e4c 86 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132669\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e19\u0e15\u0e32 199 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132669 \u0e1a\u0e08.\u0e01\u0e31\u0e19\u0e15\u0e32 199 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 699\/45  \u0e16\u0e19\u0e19\u0e27\u0e07\u0e28\u0e4c\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132758\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132758 \u0e1a\u0e08.\u0e0b\u0e39\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e31\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 merchandise \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 688\/40 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132766\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2d\u0e31\u0e19\u0e17\u0e34\u0e40\u0e21\u0e17 \u0e40\u0e27\u0e25\u0e18\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132766 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e2d\u0e31\u0e19\u0e17\u0e34\u0e40\u0e21\u0e17 \u0e40\u0e27\u0e25\u0e18\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1a\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (web application) \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1a\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 (mobile  application) \u0e41\u0e25\u0e30\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 688\/40 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e1b\u0e32\u0e23\u0e4c\u0e04 \u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132928\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e23\u0e34\u0e25\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132928 \u0e1a\u0e08.\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e23\u0e34\u0e25\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/20  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e21\u0e34\u0e15\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023266\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17 \u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023266 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e17 \u0e22\u0e39\u0e44\u0e19\u0e40\u0e15\u0e47\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e0a\u0e21\u0e1e\u0e39 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0145569004610\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004610 \u0e1a\u0e08.\u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 47722 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001637\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08.\u0e2d\u0e35.\u0e08\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77306\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77306\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001637 \u0e1a\u0e08.\u0e40\u0e08.\u0e2d\u0e35.\u0e08\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 77306 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22-\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32-\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23  \u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003050\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e40\u0e01\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003050 \u0e2b\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e40\u0e01\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-14 500000 28199 \u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e27\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e14 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e31\u0e48\u0e07\u0e15\u0e27\u0e07\u0e27\u0e31\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e22\u0e4c \u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a(calibration) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e27\u0e0a\u0e31\u0e48\u0e07\u0e15\u0e27\u0e07\u0e27\u0e31\u0e14 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 11\/226  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037231\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04\u0e14\u0e35\u0e49 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037231 \u0e1a\u0e08.\u0e42\u0e08 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04\u0e14\u0e35\u0e49 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a  \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 314\/79  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009416\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e44\u0e0b\u0e07\u0e48\u0e2d\u0e19\u0e23\u0e30\u0e22\u0e2d\u0e07168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009416 \u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e44\u0e0b\u0e07\u0e48\u0e2d\u0e19\u0e23\u0e30\u0e22\u0e2d\u0e07168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 6\/4  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0f\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009424\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009424 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e35\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e25\u0e14\u0e23\u0e34\u0e49\u0e27\u0e23\u0e2d\u0e22 \u0e22\u0e01\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a \u0e17\u0e23\u0e35\u0e17\u0e40\u0e21\u0e49\u0e19\u0e15\u0e4c \u0e19\u0e27\u0e14 \u0e01\u0e14\u0e2a\u0e34\u0e27\u0e17\u0e31\u0e48\u0e27\u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e27 \u0e1d\u0e49\u0e32 \u0e01\u0e23\u0e30 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 357\/26  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0225569002225\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e1f\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002225 \u0e1a\u0e08.\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e1f\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e25\u0e33\u0e44\u0e22 \u0e21\u0e31\u0e07\u0e04\u0e38\u0e14 \u0e17\u0e38\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e31\u0e1b\u0e1b\u0e30\u0e23\u0e14 \u0e41\u0e2d\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e2a\u0e49\u0e21 \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e41\u0e01\u0e49\u0e27\u0e21\u0e31\u0e07\u0e01\u0e23 \u0e01\u0e25\u0e49\u0e27\u0e22 \u0e01\u0e23\u0e30\u0e17\u0e49\u0e2d\u0e19 \u0e41\u0e15\u0e07\u0e42\u0e21 \u0e21\u0e30\u0e21\u0e48\u0e27\u0e07 \u0e01\u0e35\u0e27\u0e35\u0e48 \u0e1d\u0e23\u0e31\u0e48\u0e07 \u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e2a\u0e15\u0e2d\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e40\u0e07\u0e32\u0e30 \u0e17\u0e31\u0e1a\u0e17\u0e34\u0e21 \u0e25\u0e2d\u0e07\u0e01\u0e2d\u0e07 \u0e25\u0e32\u0e07\u0e2a\u0e32\u0e14 \u0e2a\u0e25\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e44\u0e21\u0e49\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 132  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007285\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19 \u0e2d\u0e2d\u0e1f \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 (2019) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007285 \u0e1a\u0e08.\u0e04\u0e27\u0e35\u0e19 \u0e2d\u0e2d\u0e1f \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25 (2019) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 14111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 171  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0403569003121\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e27\u0e19\u0e4c\u0e0b\u0e33\u0e2a\u0e39\u0e07\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11029\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11029\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003121 \u0e2b\u0e08.\u0e44\u0e27\u0e19\u0e4c\u0e0b\u0e33\u0e2a\u0e39\u0e07 2569-07-14 500000 11029 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e38\u0e23\u0e32\u0e1c\u0e25\u0e44\u0e21\u0e49 (\u0e44\u0e27\u0e19\u0e4c) \u88fd\u9020 430  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0415569003670\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e1e\u0e27\u0e23\u0e32 \u0e42\u0e01\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003670 \u0e1a\u0e08.\u0e19\u0e1e\u0e27\u0e23\u0e32 \u0e42\u0e01\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0453569001055\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d.\u0e1e\u0e35. \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 101\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001055 \u0e2b\u0e08.\u0e40\u0e2d.\u0e1e\u0e35. \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 101 2569-07-14 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 27\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0475569001499\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e0a\u0e31\u0e22\u0e18\u0e19\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46695\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46695\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0475569001499 \u0e1a\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e0a\u0e31\u0e22\u0e18\u0e19\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 46695 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e02\u0e27\u0e14 \u0e40\u0e28\u0e29\u0e40\u0e2b\u0e25\u0e47\u0e01  \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e28\u0e29\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004551\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004551 \u0e1a\u0e08.\u0e1b\u0e31\u0e49\u0e19\u0e08\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e2b\u0e19\u0e49\u0e32\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e33\u0e0b\u0e39\u0e0a\u0e34 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07  \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e39\u0e23\u0e34\u0e21\u0e34 \u0e0b\u0e32\u0e0b\u0e34\u0e21\u0e34 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e0b\u0e39\u0e0a\u0e34 \u0e2b\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u88fd\u9020 63  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0615569000571\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000571 \u0e1a\u0e08.\u0e42\u0e0a\u0e04\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e43\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 94\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0655569002264\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0a\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002264 \u0e1a\u0e08.\u0e44\u0e0a\u0e22\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 51\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0775569002999\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e14\u0e35 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002999 \u0e1a\u0e08.\u0e14\u0e39\u0e14\u0e35 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 1 \u0e0b\u0e2d\u0e22 2 \u0e02\u0e49\u0e32\u0e07\u0e42\u0e1a\u0e2a\u0e16\u0e4c\u0e04\u0e23\u0e34\u0e2a\u0e15\u0e4c \u0e16\u0e19\u0e19\u0e1e\u0e34\u0e17\u0e31\u0e01\u0e29\u0e4c\u0e0a\u0e32\u0e15\u0e34 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0805569002726\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e2a\u0e41\u0e01\u0e49\u0e27 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002726 \u0e1a\u0e08.\u0e43\u0e2a\u0e41\u0e01\u0e49\u0e27 \u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 500000 35101 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e17\u0e38\u0e01\u0e23\u0e30\u0e1a\u0e1a \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 109\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0963569000291\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e0a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a\",\"province_ja\":\"\u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\",\"search_text\":\"0963569000291 \u0e2b\u0e08.\u0e40\u0e2d\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e0a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-14 500000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\/\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e15\u0e23\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 50\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e23\u0e32\u0e18\u0e34\u0e27\u0e32\u0e2a \u30ca\u30e9\u30fc\u30c6\u30a3\u30ef\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569132103\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e01\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132103 \u0e1a\u0e08.\u0e41\u0e1e\u0e47\u0e04\u0e01\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 32909 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e31\u0e19\u0e01\u0e23\u0e30\u0e41\u0e17\u0e01 \u0e41\u0e25\u0e30\u0e42\u0e1f\u0e21\u0e17\u0e35\u0e48\u0e22\u0e48\u0e2d\u0e22\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e14\u0e49\u0e17\u0e32\u0e07\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e41\u0e1b\u0e49\u0e07\u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u88fd\u9020 27\/25  \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e1a\u0e33\u0e40\u0e1e\u0e47\u0e0d \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132162\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e17\u0e35 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132162 \u0e1a\u0e08.\u0e08\u0e35\u0e17\u0e35 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 (data center) \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07 \u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 26\/56  \u0e16\u0e19\u0e19\u0e19\u0e32\u0e07\u0e25\u0e34\u0e49\u0e19\u0e08\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002445\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14\u0e44\u0e1b\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46499\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46499\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002445 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e15\u0e25\u0e2d\u0e14\u0e44\u0e1b\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 2569-07-13 500000 46499 \u0e04\u0e49\u0e32\u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e40\u0e0a\u0e37\u0e2d\u0e01\u0e1f\u0e32\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e22\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 531  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023169\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e39\u0e49\u0e1f\u0e39\u0e48668 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023169 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e20\u0e39\u0e21\u0e34\u0e2d\u0e39\u0e49\u0e1f\u0e39\u0e48668 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1a\u0e39\u0e0a\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e0a\u0e48\u0e32\u0e1a\u0e39\u0e0a\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1e\u0e23\u0e30\u0e1a\u0e39\u0e0a\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07 \u0e02\u0e2d\u0e07\u0e02\u0e25\u0e31\u0e07 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 18\/143  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0133569002411\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e34\u0e01\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002411 \u0e2b\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e34\u0e01\u0e32 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-13 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 31\/409  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0203569003033\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e49\u0e0a\u0e39\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e2a\u0e32\u0e02\u0e32 99\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003033 \u0e2b\u0e08.\u0e40\u0e08\u0e49\u0e0a\u0e39\u0e2b\u0e21\u0e39\u0e01\u0e23\u0e30\u0e17\u0e30 \u0e2a\u0e32\u0e02\u0e32 99 2569-07-13 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 340\/182  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036898\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e27\u0e23\u0e42\u0e0a\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036898 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e27\u0e23\u0e42\u0e0a\u0e15\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e22\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e1e\u0e32\u0e22 \u0e40\u0e04\u0e49\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 555\/60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001286\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e19\u0e31\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001286 \u0e2b\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e19\u0e31\u0e48\u0e07\u0e23\u0e49\u0e32\u0e19 2569-07-13 500000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 999\/16  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e0b\u0e19\u0e14\u0e4c\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e21\u0e30\u0e2b\u0e32\u0e14 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003779\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e0b\u0e35 \u0e42\u0e1b\u0e23 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003779 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e0b\u0e35 \u0e42\u0e1b\u0e23 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e2a\u0e2d\u0e07\u0e25\u0e49\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1317  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e04\u0e38\u0e13\u0e32\u0e01\u0e23 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0363569000891\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e17\u0e04\u0e41\u0e04\u0e23\u0e4c \u0e2a\u0e34\u0e23\u0e34\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000891 \u0e2b\u0e08.\u0e40\u0e17\u0e04\u0e41\u0e04\u0e23\u0e4c \u0e2a\u0e34\u0e23\u0e34 2569-07-13 500000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21 \u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e2a\u0e23\u0e30\u0e1c\u0e21 \u0e21\u0e49\u0e27\u0e19\u0e1c\u0e21 \u0e22\u0e49\u0e2d\u0e21\u0e2a\u0e35\u0e1c\u0e21 \u0e22\u0e37\u0e14\u0e1c\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e17\u0e23\u0e07\u0e1c\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e2a\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 516  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0405569006717\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e13\u0e22\u0e4c\u0e2d\u0e35\u0e2b\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006717 \u0e1a\u0e08.\u0e1a\u0e38\u0e13\u0e22\u0e4c\u0e2d\u0e35\u0e2b\u0e25\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 388\/213  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e23\u0e31\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004720\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e1e\u0e47\u0e17\u0e0a\u0e47\u0e2d\u0e1b 999\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004720 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e1e\u0e47\u0e17\u0e0a\u0e47\u0e2d\u0e1b 999 2569-07-13 500000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004746\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e2a\u0e44\u0e25\u0e14\u0e4c\u0e04\u0e32\u0e23\u0e4c\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52214\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52214\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004746 \u0e2b\u0e08.\u0e2a\u0e38\u0e14\u0e22\u0e2d\u0e14\u0e2a\u0e44\u0e25\u0e14\u0e4c\u0e04\u0e32\u0e23\u0e4c 2569-07-13 500000 52214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e23\u0e16 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 284  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004771\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004771 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-13 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 328  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015774\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e25\u0e0a\u0e34  \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01139\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01139\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015774 \u0e1a\u0e08.\u0e42\u0e25\u0e0a\u0e34  \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 01139 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u8fb2\u6797\u6c34\u7523 75  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015847\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015847 \u0e1a\u0e08.\u0e2a\u0e2d\u0e07\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 47912 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 246  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0603569001576\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49\u0e40\u0e23\u0e14\u0e1e\u0e35\u0e1a\u0e35\u0e04\u0e25\u0e31\u0e1a\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001576 \u0e2b\u0e08.\u0e40\u0e1a\u0e1a\u0e35\u0e49\u0e40\u0e23\u0e14\u0e1e\u0e35\u0e1a\u0e35\u0e04\u0e25\u0e31\u0e1a 2569-07-13 500000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0705569003154\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e0a\u0e32\u0e27\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003154 \u0e1a\u0e08.\u0e13\u0e31\u0e10\u0e0a\u0e32\u0e27\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 500000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e14\u0e34\u0e19 \u0e17\u0e23\u0e32\u0e22 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e14\u0e34\u0e19 \u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 4\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001028\",\"name_th\":\"\u0e2b\u0e08.\u0e09\u0e31\u0e15\u0e23\u0e21\u0e13\u0e35\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001028 \u0e2b\u0e08.\u0e09\u0e31\u0e15\u0e23\u0e21\u0e13\u0e35\u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22 2569-07-13 500000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/322  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0803569000969\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e27\u0e31\u0e12\u0e19\u0e32\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000969 \u0e2b\u0e08.\u0e28\u0e34\u0e23\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e27\u0e31\u0e12\u0e19\u0e32 2569-07-13 500000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e04\u0e38\u0e23\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 29\/67  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e27\u0e19\u0e1e\u0e24\u0e01\u0e29\u0e32 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0923569000208\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e31\u0e19\u0e0b\u0e32\u0e27\u0e14\u0e4c\u0e15\u0e23\u0e31\u0e07\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0923569000208 \u0e2b\u0e08.\u0e0b\u0e31\u0e19\u0e0b\u0e32\u0e27\u0e14\u0e4c\u0e15\u0e23\u0e31\u0e07 2569-07-13 500000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e08\u0e2d\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25 led \u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e1e \u0e23\u0e30\u0e1a\u0e1a\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0105569131981\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e15\u0e34\u0e07 \u0e40\u0e2d\u0e27\u0e23\u0e35\u0e15\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131981 \u0e1a\u0e08.\u0e0b\u0e31\u0e21\u0e15\u0e34\u0e07 \u0e40\u0e2d\u0e27\u0e23\u0e35\u0e15\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 500000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e30\u0e2a\u0e21  \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\\\"\\\" \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/38  \u0e0b\u0e2d\u0e22 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e3014 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132014\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132014 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21\u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 500000 85500 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u6559\u80b2 88\/115  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 29 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132065\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32\u0e17\u0e2d\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132065 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32\u0e17\u0e2d\u0e07 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 500000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e0a\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 111\/470  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 54\/1 \u0e41\u0e22\u0e01 4 (\u0e27\u0e31\u0e14\u0e40\u0e01\u0e32\u0e30 ) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569021484\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21 \u0e0a\u0e47\u0e2d\u0e1b \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021484 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e21 \u0e0a\u0e47\u0e2d\u0e1b \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 23  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569015740\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e48\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015740 \u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e48\u0e32 \u0e40\u0e21\u0e14\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 500000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0563569000627\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e32\u0e22\u0e1d\u0e19 2026\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0563569000627 \u0e2b\u0e08.\u0e2a\u0e32\u0e22\u0e1d\u0e19 2026 2569-07-11 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 11\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0573569002166\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e22\u0e14\u0e2d\u0e22\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002166 \u0e2b\u0e08.\u0e19\u0e32\u0e22\u0e14\u0e2d\u0e22\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 2569-07-11 500000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b  \u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01\u0e19\u0e49\u0e33\u0e40\u0e07\u0e35\u0e49\u0e22\u0e27\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 348\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0103569007358\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e31\u0e27 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007358 \u0e2b\u0e08.\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e31\u0e27 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-10 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 151\/5  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131280\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10749\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10749\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131280 \u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 10749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 (\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19) \u88fd\u9020 142\/4  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e25\u0e47\u0e2d\u0e01 21\u0e01 \u0e2b\u0e21\u0e2d\u0e19 43 \u0e0b\u0e2d\u0e22 \u0e08\u0e38\u0e2c\u0e32 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023045\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e49\u0e42\u0e2b \u0e42\u0e1e\u0e40\u0e27\u0e19\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023045 \u0e1a\u0e08.\u0e42\u0e2d\u0e49\u0e42\u0e2b \u0e42\u0e1e\u0e40\u0e27\u0e19\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 188\/49  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026044\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e2a\u0e35\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026044 \u0e1a\u0e08.\u0e1e\u0e39\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e2a\u0e35\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 45202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16 \u0e17\u0e33\u0e2a\u0e35 \u0e1b\u0e30 \u0e1c\u0e38 \u0e0b\u0e48\u0e2d\u0e21\u0e0a\u0e48\u0e27\u0e07\u0e25\u0e48\u0e32\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026133\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e01\u0e32\u0e42\u0e15\u0e30 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026133 \u0e1a\u0e08.\u0e19\u0e32\u0e01\u0e32\u0e42\u0e15\u0e30 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 87\/112  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e2a\u0e34\u0e23\u0e34 \u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002364\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e40\u0e1e\u0e25\u0e34\u0e19\u0e14\u0e35\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002364 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e1f \u0e40\u0e1e\u0e25\u0e34\u0e19\u0e14\u0e35 2569-07-10 500000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19            \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569036537\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036537 \u0e1a\u0e08.\u0e1b\u0e4a\u0e2d\u0e1b \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e0b\u0e4c \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (software as a service) \u60c5\u5831\u901a\u4fe1\u30fbit 212\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036570\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e1a\u0e35 \u0e41\u0e04\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86901\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86901\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036570 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e1a\u0e35 \u0e41\u0e04\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 86901 \u0e08\u0e31\u0e14\u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e40\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u533b\u7642\u30fb\u798f\u7949 99\/82  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e40\u0e2a\u0e07\u0e21\u0e13\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036600\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e2a 1989 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036600 \u0e1a\u0e08.\u0e41\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e2a 1989 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 34  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0375569000388\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e42\u0e04 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0375569000388 \u0e1a\u0e08.\u0e42\u0e04\u0e42\u0e04 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001608\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e27\u0e31\u0e12\u0e19\u0e32 999\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001608 \u0e2b\u0e08.\u0e44\u0e17\u0e22\u0e27\u0e31\u0e12\u0e19\u0e32 999 2569-07-10 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 341  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0463569000717\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e19\u0e19\u0e35\u0e48\u0e1e\u0e34\u0e07\u0e04\u0e4c 69\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000717 \u0e2b\u0e08.\u0e40\u0e08\u0e19\u0e19\u0e35\u0e48\u0e1e\u0e34\u0e07\u0e04\u0e4c 69 2569-07-10 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0485569000891\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e19\u0e17\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000891 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e40\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e19\u0e17\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 \u5efa\u8a2d 31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0505569015723\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e2d\u0e22 \u0e23\u0e34\u0e0a \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015723 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e2d\u0e22 \u0e23\u0e34\u0e0a \u0e04\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e19\u0e17\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e1b\u0e35 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e19\u0e02\u0e31\u0e1a \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 103\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015731\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e35\u0e22\u0e07\u0e01\u0e34\u0e15\u0e15\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015731 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e35\u0e22\u0e07\u0e01\u0e34\u0e15\u0e15\u0e34 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 298  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001641\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33122\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33122\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001641 \u0e1a\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 33122 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e14\u0e39\u0e41\u0e25 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u88fd\u9020 271  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004462\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004462 \u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e01\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21 \u0e40\u0e22\u0e25\u0e25\u0e35\u0e48 \u0e1a\u0e4a\u0e27\u0e22\u0e41\u0e0a\u0e48\u0e2d\u0e34\u0e48\u0e21 \u0e0a\u0e47\u0e2d\u0e01\u0e42\u0e01\u0e41\u0e25\u0e47\u0e15 \u0e25\u0e39\u0e01\u0e2d\u0e21 \u0e16\u0e31\u0e48\u0e27\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e31\u0e25\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e34\u0e2a\u0e15\u0e32\u0e0a\u0e34\u0e42\u0e2d \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07 \u0e43\u0e1a\u0e0a\u0e32  \u0e40\u0e08\u0e35\u0e22\u0e27\u0e01\u0e39\u0e48\u0e2b\u0e25\u0e32\u0e19 \u0e40\u0e2b\u0e47\u0e14\u0e2b\u0e2d\u0e21\u0e40\u0e2b\u0e47\u0e14\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e32\u0e2b\u0e23\u0e48\u0e32\u0e22\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e01\u0e32\u0e25\u0e31\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 361  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0675569001489\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10131\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10131\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001489 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e08 \u0e1f\u0e39\u0e49\u0e14 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 10131 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b  \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e30\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0715569002590\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002590 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000641\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e27\u0e22\u0e23\u0e27\u0e22\u0e1b\u0e31\u0e07\u0e01\u0e27\u0e48\u0e32\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000641 \u0e2b\u0e08.\u0e2a\u0e27\u0e22\u0e23\u0e27\u0e22\u0e1b\u0e31\u0e07\u0e01\u0e27\u0e48\u0e32 2569-07-10 500000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07) \u533b\u7642\u30fb\u798f\u7949 56  \u0e16\u0e19\u0e19\u0e40\u0e13\u0e23\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0775569002964\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e41\u0e1e\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002964 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e41\u0e1e\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e43\u0e19\u0e04\u0e14\u0e35\u0e41\u0e1e\u0e48\u0e07 \u0e04\u0e14\u0e35\u0e2d\u0e32\u0e0d\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e14\u0e35\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e17\u0e33\u0e04\u0e33\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e25\u0e32\u0e22\u0e21\u0e37\u0e2d\u0e0a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 (\u0e42\u0e19\u0e15\u0e32\u0e23\u0e35\u0e1b\u0e31\u0e1a\u0e25\u0e34\u0e01) \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 838  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0903569001565\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001565 \u0e2b\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 2569-07-10 500000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e15\u0e48\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e23\u0e07\u0e2a\u0e39\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e2a\u0e16\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 82\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005651\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e14\u0e35 \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64929\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64929\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005651 \u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e14\u0e35 \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500000 64929 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e07\u0e34\u0e19\u0e01\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e01\u0e39\u0e49\u0e22\u0e37\u0e21\u0e40\u0e07\u0e34\u0e19\u0e19\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e1d\u0e32\u0e01 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e27\u0e49\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23  \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e07\u0e34\u0e19\u0e17\u0e38\u0e19  \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e1f\u0e2d\u0e07\u0e0b\u0e34\u0e40\u0e2d\u0e23\u0e4c \u91d1\u878d\u30fb\u4fdd\u967a 89\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007269\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e21\u0e40\u0e21\u0e49\u0e19\u0e15\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007269 \u0e2b\u0e08.\u0e42\u0e21\u0e40\u0e21\u0e49\u0e19\u0e15\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 2569-07-09 500000 14120 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30 \u0e2a\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 101\/111  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007293\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e34\u0e14\u0e32\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007293 \u0e2b\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e34\u0e14\u0e32 2569-07-09 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 48\/145  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 55\/8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129595\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e13\u0e31\u0e10 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129595 \u0e1a\u0e08.\u0e15\u0e31\u0e07\u0e02\u0e2d\u0e07\u0e13\u0e31\u0e10 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 425\/12  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129609\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e41\u0e1b\u0e14\u0e17\u0e31\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129609 \u0e1a\u0e08.\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e32\u0e21\u0e41\u0e1b\u0e14\u0e17\u0e31\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u60c5\u5831\u901a\u4fe1\u30fbit 138\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e3236 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129633\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129633 \u0e1a\u0e08.\u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e10\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e1b\u0e31\u0e08\u0e09\u0e34\u0e21\u0e19\u0e34\u0e40\u0e17\u0e28 \u0e04\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 8  \u0e0b\u0e2d\u0e22 1 \u0e16\u0e19\u0e19\u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129714\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e01 \u0e40\u0e1f\u0e25\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129714 \u0e1a\u0e08.\u0e2a\u0e1b\u0e32\u0e23\u0e4c\u0e01 \u0e40\u0e1f\u0e25\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49  \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e27\u0e07\u0e01\u0e38\u0e0d\u0e41\u0e08 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e15\u0e38\u0e4a\u0e01\u0e15\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e20\u0e32\u0e0a\u0e19\u0e30 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e32\u0e41\u0e23\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 454\/28  \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e44\u0e1c\u0e48\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129790\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e34\u0e2a \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129790 \u0e1a\u0e08.\u0e44\u0e2d\u0e23\u0e34\u0e2a \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e02\u0e49\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e48\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e14\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e2a\u0e23\u0e30\u0e17\u0e38\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 138\/1  \u0e0b\u0e2d\u0e22 \u0e1e\u0e38\u0e17\u0e18\u0e1a\u0e39\u0e0a\u0e3236 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130127\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e1e\u0e35 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130127 \u0e1a\u0e08.\u0e17\u0e39\u0e1e\u0e35 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 70209 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 9\/105  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e25\u0e31\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 101 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130160\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e31\u0e0a\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130160 \u0e1a\u0e08.\u0e17\u0e31\u0e0a\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 62011 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 139  \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e49\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130461\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32\u0e17\u0e2d\u0e07 2559 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130461 \u0e1a\u0e08.\u0e18\u0e32\u0e23\u0e32\u0e17\u0e2d\u0e07 2559 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e0a\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 111\/470  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 54\/1 \u0e41\u0e22\u0e01 4 (\u0e27\u0e31\u0e14\u0e40\u0e01\u0e32\u0e30) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130518\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e25\u0e31\u0e22\u0e41\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130518 \u0e1a\u0e08.\u0e21\u0e32\u0e25\u0e31\u0e22\u0e41\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e1c\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e23\u0e38\u0e29 \u0e2a\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u88fd\u9020 110\/17  \u0e16\u0e19\u0e19\u0e27\u0e38\u0e12\u0e32\u0e01\u0e32\u0e2a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130712\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35 \u0e25\u0e35\u0e01\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130712 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35 \u0e25\u0e35\u0e01\u0e31\u0e25  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 2140  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002356\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e23\u0e34\u0e2a \u0e42\u0e1f\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002356 \u0e2b\u0e08.\u0e27\u0e32\u0e23\u0e34\u0e2a \u0e42\u0e1f\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-09 500000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 149\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022715\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35\u0e44\u0e2d\u0e17\u0e35\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022715 \u0e1a\u0e08.\u0e40\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1e\u0e35\u0e44\u0e2d\u0e17\u0e35\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0a\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 239\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022812\",\"name_th\":\"\u0e1a\u0e08. \u0e21\u0e39\u0e40\u0e01\u0e47\u0e19 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46592\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46592\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022812 \u0e1a\u0e08. \u0e21\u0e39\u0e40\u0e01\u0e47\u0e19 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 46592 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e22\u0e49\u0e32\u0e22 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 187\/83  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022910\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e27\u0e32\u0e19 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022910 \u0e1a\u0e08.\u0e01\u0e31\u0e07\u0e27\u0e32\u0e19 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u88fd\u9020 88\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0133569002291\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e34\u0e27\u0e23\u0e23\u0e18\u0e19\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e25\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002291 \u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e34\u0e27\u0e23\u0e23\u0e18\u0e19\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e25 2569-07-09 500000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002321\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e0a\u0e42\u0e25\u0e21\u0e32 \u0e2a\u0e15\u0e23\u0e35\u0e17\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002321 \u0e2b\u0e08.\u0e41\u0e0a\u0e42\u0e25\u0e21\u0e32 \u0e2a\u0e15\u0e23\u0e35\u0e17\u0e1f\u0e39\u0e49\u0e14 2569-07-09 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 12\/36   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4-10 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e1a\u0e38\u0e0d\u0e04\u0e38\u0e49\u0e21 7 \u0e16\u0e19\u0e19\u0e1a\u0e38\u0e0d\u0e04\u0e38\u0e49\u0e21 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002356\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002356 \u0e2b\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-09 500000 80200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19 \u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49  \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e38\u0e01\u0e23\u0e38\u0e01  \u0e44\u0e21\u0e49\u0e01\u0e31\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1178\/52  \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021247\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04\u0e1a\u0e35 \u0e2d\u0e2d\u0e25 \u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e15\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021247 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e04\u0e1a\u0e35 \u0e2d\u0e2d\u0e25 \u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e15\u0e34\u0e1f\u0e34\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/349  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1f\u0e49\u0e32\u0e1b\u0e34\u0e22\u0e23\u0e21\u0e22\u0e4c \u0e40\u0e17\u0e19\u0e42\u0e14\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0143569001155\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e17\u0e49\u0e2d\u0e1b \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e0b\u0e35\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001155 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e17\u0e49\u0e2d\u0e1b \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e0b\u0e35 2569-07-09 500000 21001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 3\/59  \u0e16\u0e19\u0e19\u0e40\u0e14\u0e0a\u0e32\u0e27\u0e38\u0e18 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001556\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21.88 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001556 \u0e1a\u0e08.\u0e1e\u0e35.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21.88 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036171\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e25\u0e32\u0e23\u0e49\u0e32\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036171 \u0e1a\u0e08.\u0e1b\u0e25\u0e32\u0e23\u0e49\u0e32\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 47219 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 298\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003671\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e06\u0e29\u0e34\u0e15\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003671 \u0e1a\u0e08.\u0e42\u0e06\u0e29\u0e34\u0e15\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0245569003680\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e49 \u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003680 \u0e1a\u0e08.\u0e40\u0e2e\u0e49 \u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/5  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e16\u0e31\u0e48\u0e27 2 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0343569001846\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e1a\u0e32\u0e40\u0e1e\u0e0a\u0e23 678\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46209\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46209\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001846 \u0e2b\u0e08.\u0e0a\u0e1a\u0e32\u0e40\u0e1e\u0e0a\u0e23 678 2569-07-09 500000 46209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/217  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0403569003023\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e33\u0e1b\u0e32\u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2a\u0e1b\u0e32\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003023 \u0e2b\u0e08.\u0e08\u0e33\u0e1b\u0e32\u0e21\u0e32\u0e2a\u0e2a\u0e32\u0e08\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2a\u0e1b\u0e32 2569-07-09 500000 96101 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e27\u0e14\u0e41\u0e25\u0e30\u0e2a\u0e1b\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 686\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e19\u0e19\u0e21\u0e48\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004550\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e40\u0e2d\u0e2a 2044\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004550 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35\u0e40\u0e2d\u0e2a 2044 2569-07-09 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004568\",\"name_th\":\"\u0e2b\u0e08.433 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82191\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82191\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004568 \u0e2b\u0e08.433 \u0e1b\u0e23\u0e34\u0e49\u0e19\u0e17\u0e4c 2569-07-09 500000 82191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 3  \u0e16\u0e19\u0e19\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e14\u0e49\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e32\u0e04\u0e15 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015537\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e0b\u0e49\u0e27\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e0a\u0e49\u0e32\u0e07\u0e40\u0e1c\u0e37\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10749\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10749\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015537 \u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e0b\u0e49\u0e27\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e0a\u0e49\u0e32\u0e07\u0e40\u0e1c\u0e37\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 10749 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 (\u0e1a\u0e31\u0e27\u0e25\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19) \u88fd\u9020 94\/2   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 e05 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015596\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e38\u0e25\u0e01\u0e31\u0e19\u0e22\u0e32\u0e41\u0e25\u0e30\u0e01\u0e38\u0e25\u0e20\u0e31\u0e2a\u0e2a\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015596 \u0e1a\u0e08.\u0e01\u0e38\u0e25\u0e01\u0e31\u0e19\u0e22\u0e32\u0e41\u0e25\u0e30\u0e01\u0e38\u0e25\u0e20\u0e31\u0e2a\u0e2a\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569002123\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e13\u0e23\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46693\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46693\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002123 \u0e2b\u0e08.\u0e40\u0e13\u0e23\u0e01\u0e32\u0e23\u0e22\u0e32\u0e07 2569-07-09 500000 46693 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23          \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 840  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e21\u0e48\u0e41\u0e2d\u0e1a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0703569000480\",\"name_th\":\"\u0e2b\u0e08.\u0e21.\u0e2b\u0e21\u0e39 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e2d\u0e23\u0e4c\u0e04\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0703569000480 \u0e2b\u0e08.\u0e21.\u0e2b\u0e21\u0e39 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e1e\u0e2d\u0e23\u0e4c\u0e04 2569-07-09 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e38\u0e01 \u0e02\u0e19\u0e21 \u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u5bbf\u6cca\u30fb\u98f2\u98df 254  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0715569002573\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e35\u0e2d\u0e2d\u0e19 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002573 \u0e1a\u0e08.\u0e19\u0e35\u0e2d\u0e2d\u0e19 \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 62011 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e02\u0e22\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1aai \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e04\u0e25\u0e31\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c gpu \u0e41\u0e1a\u0e1a\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e44\u0e1b\u0e08\u0e19\u0e16\u0e36\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14\u0e41\u0e25\u0e30\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u60c5\u5831\u901a\u4fe1\u30fbit 279\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0723569000633\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e32\u0e13\u0e34\u0e2a\u0e23\u0e32 \u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"87100\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"87100\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000633 \u0e2b\u0e08.\u0e1b\u0e32\u0e13\u0e34\u0e2a\u0e23\u0e32 \u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e42\u0e2e\u0e21 2569-07-09 500000 87100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e01\u0e1e\u0e34\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19 \u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e23\u0e37\u0e49\u0e2d\u0e23\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30\u0e1e\u0e36\u0e48\u0e07\u0e1e\u0e34\u0e07 \u533b\u7642\u30fb\u798f\u7949 248\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0845569010214\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e40\u0e08 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010214 \u0e1a\u0e08.\u0e17\u0e35 \u0e40\u0e08 \u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e41\u0e1b\u0e25\u0e19 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e41\u0e1a\u0e1a\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 62\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0903569001531\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04 \u0e27\u0e34\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001531 \u0e2b\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04 \u0e27\u0e34\u0e19 2569-07-09 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 722  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0925569000978\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569000978 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2b\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e14 \u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e49\u0e2d\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 89\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0935569000820\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e2d \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0935569000820 \u0e1a\u0e08. \u0e40\u0e2d\u0e47\u0e19\u0e44\u0e2d \u0e2d\u0e2d\u0e14\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 385\/7  \u0e16\u0e19\u0e19\u0e2d\u0e20\u0e31\u0e22\u0e1a\u0e23\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0103569007056\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e14\u0e35 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e48\u0e22\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007056 \u0e2b\u0e08.\u0e1a\u0e35\u0e14\u0e35 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e48\u0e22\u0e4c 2569-07-08 500000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 118  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1b\u0e34\u0e48\u0e19\u0e2a\u0e21\u0e23 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e19\u0e15\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 116 \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e2151 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007196\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007196 \u0e2b\u0e08.\u0e18\u0e19\u0e20\u0e31\u0e17\u0e23 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 2569-07-08 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 206  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e35\u0e22\u0e19\u0e17\u0e30\u0e40\u0e25 26 \u0e41\u0e22\u0e01 6-1 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007218\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e2a\u0e19\u0e31\u0e19\u0e17\u0e4c24 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007218 \u0e2b\u0e08.\u0e23\u0e2a\u0e19\u0e31\u0e19\u0e17\u0e4c24 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-08 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e2d\u0e1a\u0e23\u0e21 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 418\/159  \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128866\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e25\u0e47\u0e01\u0e44\u0e1b\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128866 \u0e1a\u0e08.\u0e17\u0e33\u0e08\u0e32\u0e01\u0e40\u0e25\u0e47\u0e01\u0e44\u0e1b\u0e43\u0e2b\u0e0d\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a \u0e07\u0e32\u0e19\u0e27\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23  \u0e07\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e41\u0e25\u0e30\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e07\u0e32\u0e19\u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e32\u0e07 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 45\/1  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e2a\u0e31\u0e19\u0e15\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129161\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2e\u0e2a\u0e17\u0e4c\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129161 \u0e1a\u0e08.\u0e42\u0e2e\u0e2a\u0e17\u0e4c\u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e25\u0e30\u0e04\u0e23\u0e40\u0e27\u0e17\u0e35 \u0e19\u0e32\u0e0e\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e14\u0e19\u0e15\u0e23\u0e35\u0e41\u0e25\u0e30\u0e21\u0e2b\u0e23\u0e2a\u0e1e\u0e2d\u0e37\u0e48\u0e19\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 1030\/1  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022561\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e23\u0e2b\u0e21\u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10293\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10293\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022561 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e23\u0e2b\u0e21\u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 10293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e2a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e1b\u0e25\u0e32\u0e23\u0e49\u0e32 \u88fd\u9020 431\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025625\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e44\u0e21\u0e25\u0e4c\u0e41\u0e17\u0e47\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32909\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32909\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025625 \u0e1a\u0e08.\u0e2a\u0e44\u0e21\u0e25\u0e4c\u0e41\u0e17\u0e47\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 32909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e34\u0e27\u0e2d\u0e32\u0e23\u0e4c\u0e42\u0e04\u0e49\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07, \u0e1b\u0e25\u0e2d\u0e01\u0e04\u0e2d, \u0e1b\u0e49\u0e32\u0e22\u0e2b\u0e49\u0e2d\u0e22\u0e04\u0e2d, \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19, \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e07\u0e17\u0e32\u0e07 \u88fd\u9020 89\/33  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e18\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021085\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021085 \u0e1a\u0e08.\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e2d\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u4e0d\u52d5\u7523 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004458\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e17\u0e35 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004458 \u0e1a\u0e08.\u0e1e\u0e35\u0e0b\u0e35\u0e17\u0e35 \u0e2d\u0e30\u0e42\u0e01\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a \u0e1b\u0e38\u0e4b\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e38\u0e4b\u0e22\u0e40\u0e04\u0e21\u0e35 \u0e1b\u0e38\u0e4b\u0e22\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e1b\u0e38\u0e4b\u0e22\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e18\u0e32\u0e15\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e37\u0e0a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569035956\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e23\u0e34 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035956 \u0e1a\u0e08.\u0e44\u0e14\u0e23\u0e34 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 305\/76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035964\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e04\u0e31\u0e1e \u0e1e\u0e31\u0e17\u0e22\u0e32 69 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035964 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e04\u0e31\u0e1e \u0e1e\u0e31\u0e17\u0e22\u0e32 69 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 341\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0255569001962\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0255569001962 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e0b\u0e35 \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 977  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e19\u0e1e\u0e24\u0e01\u0e29\u0e32 \u0e40\u0e14\u0e2d\u0e30\u0e44\u0e1e\u0e23\u0e27\u0e35\u0e48\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e42\u0e1b\u0e48\u0e07\u0e44\u0e1c\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002648\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e22\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002648 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e22\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c 2569-07-08 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 852  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e19\u0e32\u0e23\u0e32\u0e22\u0e13\u0e4c \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0405569006539\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e40\u0e04\u0e23\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006539 \u0e1a\u0e08.\u0e40\u0e27\u0e25\u0e18\u0e4c \u0e40\u0e04\u0e23\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 47711 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e41\u0e25\u0e30\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e14\u0e47\u0e01, \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e14\u0e47\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 106  \u0e0b\u0e2d\u0e22 \u0e19\u0e34\u0e01\u0e23\u0e2a\u0e33\u0e23\u0e32\u0e0d 3 \u0e16\u0e19\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0453569001012\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e0a\u0e31\u0e22 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569001012 \u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e0a\u0e31\u0e22 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c 2569-07-08 500000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0525569001617\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 54 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47733\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47733\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001617 \u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19 54 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 47733 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e15\u0e49\u0e19\u0e01\u0e25\u0e49\u0e32 \u0e44\u0e21\u0e49\u0e14\u0e2d\u0e01 \u0e44\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e44\u0e21\u0e49\u0e22\u0e37\u0e19\u0e15\u0e49\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0653569001070\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e17\u0e35. \u0e40\u0e2e\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001070 \u0e2b\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e17\u0e35. \u0e40\u0e2e\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-08 500000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32-\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07  \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e17\u0e32\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e08\u0e31\u0e01\u0e2a\u0e32\u0e19  \u0e1c\u0e49\u0e32  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0725569002069\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e42\u0e2d\u0e44\u0e23\u0e0b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002069 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e42\u0e2d\u0e44\u0e23\u0e0b\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 500000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 198  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569127967\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e2d\u0e35\u0e27\u0e35 \u0e04\u0e32\u0e23\u0e4c\u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127967 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e2d\u0e35\u0e27\u0e35 \u0e04\u0e32\u0e23\u0e4c\u0e40\u0e23\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e43\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e2d\u0e01\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 672\/2  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1a\u0e33\u0e40\u0e1e\u0e47\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128050\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e44\u0e0b\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128050 \u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e44\u0e25\u0e1f\u0e4c\u0e44\u0e0b\u0e41\u0e2d\u0e19\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e15\u0e35\u0e19\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 521\/173  \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128190\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e14\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0105569128190 \u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e14\u0e4c \u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 82302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e41\u0e2a\u0e14\u0e07\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e23\u0e27\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e01\u0e47\u0e15\u0e32\u0e21 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 100\/26  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e38\u0e02 \u0e40\u0e2d\u0e2a\u0e40\u0e01\u0e15 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-345 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569128530\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128530 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e2a\u0e1a\u0e35 \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 47722 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/7-8-9-10  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 19 (\u0e27\u0e31\u0e12\u0e19\u0e32) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022359\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e42\u0e2d \u0e22\u0e39\u0e19\u0e34\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022359 \u0e1a\u0e08.\u0e21\u0e34\u0e42\u0e2d \u0e22\u0e39\u0e19\u0e34\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e16\u0e19\u0e19\u0e01\u0e34\u0e48\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025269\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025269 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 71102 \u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 68\/102  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e19\u0e32\u0e25\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025277\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e27\u0e32\u0e22 \u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 89 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82920\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82920\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025277 \u0e1a\u0e08.\u0e40\u0e04\u0e41\u0e2d\u0e25\u0e27\u0e32\u0e22 \u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e08\u0e34\u0e49\u0e07 89 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 82920 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2b\u0e48\u0e2d\u0e2b\u0e38\u0e49\u0e21\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e16\u0e38\u0e07\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e16\u0e38\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e16\u0e38\u0e07\u0e02\u0e22\u0e30 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 89\/48  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025366\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e35\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025366 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e35\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 27101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 229\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025510\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e01\u0e34\u0e49\u0e19 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025510 \u0e1a\u0e08.\u0e1a\u0e34\u0e01\u0e34\u0e49\u0e19 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 59\/129  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035786\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e16\u0e39 \u0e17\u0e32\u0e40\u0e25\u0e19\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035786 \u0e1a\u0e08.\u0e0b\u0e34\u0e07\u0e16\u0e39 \u0e17\u0e32\u0e40\u0e25\u0e19\u0e17\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e27\u0e35\u0e0b\u0e48\u0e32 \u0e41\u0e08\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32-\u0e41\u0e08\u0e49\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27 90 \u0e27\u0e31\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 98\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001219\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e01\u0e24\u0e15 2569\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001219 \u0e2b\u0e08.\u0e19\u0e32\u0e23\u0e32\u0e01\u0e24\u0e15 2569 2569-07-07 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e21\u0e2a\u0e14, \u0e19\u0e21\u0e40\u0e1b\u0e23\u0e35\u0e49\u0e22\u0e27,\u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/30  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e38\u0e02 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0233569000107\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e22\u0e39 \u0e1f\u0e23\u0e38\u0e4a\u0e15\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e32\u0e14\",\"province_ja\":\"\u30c8\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0233569000107 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e2d \u0e40\u0e2d\u0e47\u0e21 \u0e22\u0e39 \u0e1f\u0e23\u0e38\u0e4a\u0e15 2569-07-07 500000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e15\u0e23\u0e32\u0e14 \u30c8\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0313569000971\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2e\u0e07\u0e2a\u0e2d\u0e07\u0e41\u0e1b\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569000971 \u0e2b\u0e08.\u0e40\u0e2e\u0e07\u0e2a\u0e2d\u0e07\u0e41\u0e1b\u0e14 2569-07-07 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e4a\u0e32\u0e0b\u0e2b\u0e38\u0e07\u0e15\u0e49\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07 \u0e1c\u0e31\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 106\/2  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e40\u0e17\u0e1e \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0333569000637\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e44\u0e17\u0e23\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000637 \u0e2b\u0e08.\u0e1e\u0e35\u0e17\u0e35 \u0e44\u0e17\u0e23\u0e4c \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-07 500000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0385569000477\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c\",\"province_ja\":\"\u30d6\u30f3\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0385569000477 \u0e1a\u0e08.\u0e21\u0e35\u0e21\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1a\u0e36\u0e07\u0e01\u0e32\u0e2c \u30d6\u30f3\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006474\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e01\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006474 \u0e1a\u0e08.\u0e42\u0e0a\u0e01\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 70\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015359\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e15\u0e23 108\u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015359 \u0e1a\u0e08.\u0e21\u0e34\u0e15\u0e23 108\u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 419  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015383\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e27\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015383 \u0e1a\u0e08.\u0e42\u0e04\u0e27\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0655569002175\",\"name_th\":\"\u0e1a\u0e08.\u0e2a.\u0e44\u0e01\u0e48\u0e2a\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002175 \u0e1a\u0e08.\u0e2a.\u0e44\u0e01\u0e48\u0e2a\u0e14\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e44\u0e01\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e0a\u0e34\u0e27\u0e15\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e02\u0e2d\u0e07\u0e44\u0e01\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0713569000528\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e49\u0e32\u0e27\u0e15\u0e49\u0e21\u0e2b\u0e31\u0e27\u0e19\u0e32\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0713569000528 \u0e2b\u0e08.\u0e02\u0e49\u0e32\u0e27\u0e15\u0e49\u0e21\u0e2b\u0e31\u0e27\u0e19\u0e32 2569-07-07 500000 56101 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e43\u0e19\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23\/\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 185-185\/1  \u0e16\u0e19\u0e19\u0e2d\u0e39\u0e48\u0e17\u0e2d\u0e07 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006854\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e41\u0e21\u0e19\u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07(\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46433\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46433\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006854 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e41\u0e21\u0e19\u0e1f\u0e34\u0e0a\u0e0a\u0e34\u0e48\u0e07(\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 46433 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e04\u0e31\u0e19\u0e40\u0e1a\u0e47\u0e14 \u0e23\u0e2d\u0e01\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e2d\u0e21 \u0e2a\u0e32\u0e22\u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e1b\u0e25\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 74\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007125\",\"name_th\":\"\u0e1a\u0e08.\u0e27.\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007125 \u0e1a\u0e08.\u0e27.\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 43210 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e19\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u5efa\u8a2d 179\/153  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e40\u0e1a\u0e25\u0e25\u0e48\u0e32 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212-\u0e1e\u0e31\u0e19\u0e17\u0e49\u0e32\u0e22\u0e19\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0843569001302\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e31\u0e22\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e2199\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001302 \u0e2b\u0e08.\u0e0a\u0e31\u0e22\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e2199 2569-07-07 500000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u8fb2\u6797\u6c34\u7523 26\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005392\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e23\u0e48\u0e32 \u0e42\u0e2d\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005392 \u0e1a\u0e08.\u0e42\u0e0b\u0e23\u0e48\u0e32 \u0e42\u0e2d\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 112  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e19\u0e34\u0e0a \u0e0b\u0e2d\u0e22 21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005431\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c 99 \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005431 \u0e1a\u0e08.\u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c 99 \u0e2d\u0e32\u0e23\u0e4c\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 500000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 18\/3 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569126804\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e25\u0e39\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126804 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e25\u0e39\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e02\u0e19\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01 \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e48\u0e27\u0e22\u0e44\u0e27\u0e49\u0e04\u0e49\u0e32\u0e07\u0e04\u0e37\u0e19 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32 \u0e2d\u0e32\u0e1a\u0e19\u0e4d\u0e49\u0e32 \u0e15\u0e31\u0e14\u0e02\u0e19 \u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 9  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126898\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126898 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e47\u0e21\u0e14\u0e35\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (e-commerce) \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/182  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 81 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022286\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e21\u0e32\u0e23\u0e35\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022286 \u0e1a\u0e08.\u0e22\u0e39\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e2d \u0e21\u0e32\u0e23\u0e35\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 98\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002127\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e4a\u0e17 \u0e17\u0e23\u0e35 \u0e1a\u0e35\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002127 \u0e2b\u0e08.\u0e40\u0e1e\u0e4a\u0e17 \u0e17\u0e23\u0e35 \u0e1a\u0e35 2569-07-06 500000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e02\u0e19 \u0e2d\u0e32\u0e1a\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 89\/1341  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e215-\u0e1a\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0123569002135\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e24\u0e15\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002135 \u0e2b\u0e08.\u0e01\u0e24\u0e15\u0e17\u0e27\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 2569-07-06 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 13\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002267\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e17\u0e40\u0e25 \u0e04\u0e2d\u0e25\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002267 \u0e2b\u0e08.\u0e40\u0e17\u0e40\u0e25 \u0e04\u0e2d\u0e25 2569-07-06 500000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e0a\u0e19\u0e34\u0e14\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e43\u0e14 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 289\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569008991\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e32\u0e40\u0e1e\u0e25\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66221\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66221\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008991 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1e\u0e32\u0e40\u0e1e\u0e25\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 66221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22) \u91d1\u878d\u30fb\u4fdd\u967a 37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0253569000484\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e04\u0e49\u0e32\u0e44\u0e21\u0e49\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0253569000484 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e04\u0e49\u0e32\u0e44\u0e21\u0e49 2569-07-06 500000 46632 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e21\u0e49\u0e22\u0e39\u0e04\u0e32\u0e25\u0e34\u0e1b\u0e15\u0e31\u0e2a \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e31\u0e14 \u0e42\u0e04\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e44\u0e21\u0e49\u0e22\u0e39\u0e04\u0e32\u0e25\u0e34\u0e1b\u0e15\u0e31\u0e2a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 525\/306  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e27\u0e19\u0e1e\u0e24\u0e01\u0e29\u0e32 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e2d\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e48\u0e07\u0e44\u0e1c\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0403569002965\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e08\u0e44\u0e14\u0e42\u0e1f\u0e19\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002965 \u0e2b\u0e08.\u0e40\u0e14\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e08\u0e44\u0e14\u0e42\u0e1f\u0e19 2569-07-06 500000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e0b\u0e48\u0e2d\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0433569000393\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e01\u0e32\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000393 \u0e2b\u0e08.\u0e23\u0e31\u0e15\u0e19\u0e01\u0e32\u0e23\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-06 500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0433569000407\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e33\u0e42\u0e0a\u0e04 2569\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000407 \u0e2b\u0e08.\u0e19\u0e33\u0e42\u0e0a\u0e04 2569 2569-07-06 500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 199  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e42\u0e1e\u0e19\u0e41\u0e1e\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e0a\u0e22\u0e32\u0e07\u0e01\u0e39\u0e23 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0495569000522\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e32 \u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47511\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47511\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0495569000522 \u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e32 \u0e1c\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 47511 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/4  \u0e16\u0e19\u0e19\u0e0a\u0e22\u0e32\u0e07\u0e01\u0e39\u0e23 \u0e02 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004363\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e01\u0e04\u0e31\u0e1a\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56301\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56301\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004363 \u0e2b\u0e08.\u0e21\u0e31\u0e01\u0e04\u0e31\u0e1a 2569-07-06 500000 56301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 61\/1  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e1b\u0e25\u0e48\u0e2d\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0645569000717\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e40\u0e17\u0e1e \u0e2a\u0e31\u0e07\u0e04\u0e42\u0e25\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"23932\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"23932\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000717 \u0e1a\u0e08.\u0e2a\u0e38\u0e40\u0e17\u0e1e \u0e2a\u0e31\u0e07\u0e04\u0e42\u0e25\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 23932 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19\u0e40\u0e1c\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e42\u0e25\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e0b\u0e23\u0e32\u0e21\u0e34\u0e04 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e34\u0e21\u0e32\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19 \u0e28\u0e34\u0e25\u0e1b\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e20  \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 203\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0645569000725\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000725 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 130  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0805569002556\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e41\u0e01\u0e49\u0e27\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002556 \u0e1a\u0e08.\u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e41\u0e01\u0e49\u0e27\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 46692 \u0e02\u0e32\u0e22\u0e1b\u0e38\u0e4b\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002564\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e2b\u0e2d\u0e21\u0e41\u0e14\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002564 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e2b\u0e2d\u0e21\u0e41\u0e14\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e21\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e2d\u0e21\u0e41\u0e14\u0e07 \u0e1e\u0e23\u0e34\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e2d\u0e49\u0e2d\u0e22 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 133\/3  \u0e16\u0e19\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002572\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e17\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22 \u0e1e\u0e37\u0e0a\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002572 \u0e1a\u0e08.\u0e1a\u0e38\u0e0d\u0e17\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22 \u0e1e\u0e37\u0e0a\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 500000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2b\u0e2d\u0e21\u0e41\u0e14\u0e07 \u0e1e\u0e23\u0e34\u0e01\u0e41\u0e2b\u0e49\u0e07 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e2d\u0e49\u0e2d\u0e22 \u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1e\u0e37\u0e0a\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2  \u0e0b\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e1e\u0e23\u0e30 \u0e16\u0e19\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e22\u0e32\u0e27 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569126707\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126707 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 26\/136  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e01\u0e01\u0e27\u0e34\u0e19 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126740\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e27\u0e25\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126740 \u0e1a\u0e08.\u0e17\u0e35\u0e40\u0e08 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e27\u0e25\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e04\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e04\u0e48\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 433\/1  \u0e0b\u0e2d\u0e22 \u0e19\u0e1e\u0e40\u0e01\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0253569000476\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e14\u0e27\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"02200\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"02200\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0253569000476 \u0e2b\u0e08.\u0e14\u0e32\u0e27\u0e14\u0e27\u0e07\u0e43\u0e2b\u0e21\u0e48 2569-07-05 500000 02200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e21\u0e49\u0e22\u0e39\u0e04\u0e32 \u8fb2\u6797\u6c34\u7523 150  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e23\u0e32\u0e08\u0e35\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30d7\u30e9\u30fc\u30c1\u30fc\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002567\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e04 1972\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002567 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35\u0e40\u0e04 1972 2569-07-05 500000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19 \u0e15\u0e31\u0e14\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0645569000709\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e38\u0e28\u0e25 \u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47731\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47731\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0645569000709 \u0e1a\u0e08.\u0e01\u0e38\u0e28\u0e25 \u0e27\u0e34\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 500000 47731 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e31\u0e14\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e04\u0e48\u0e32\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e31\u0e14 \u0e40\u0e08\u0e35\u0e22\u0e23\u0e30\u0e44\u0e19 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e27\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e01\u0e31\u0e1a\u0e41\u0e27\u0e48\u0e19\u0e15\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0745569007036\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e2d\u0e2a.\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007036 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27.\u0e40\u0e2d\u0e2a.\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 500000 69200 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 78\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569126537\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35 \u0e2a\u0e21\u0e34\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126537 \u0e1a\u0e08.\u0e27\u0e35 \u0e2a\u0e21\u0e34\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e2d\u0e22\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 22\/102  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2723 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126600\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e34\u0e40\u0e0b\u0e40\u0e23\u0e35\u0e22 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126600 \u0e1a\u0e08.\u0e40\u0e2d\u0e23\u0e34\u0e40\u0e0b\u0e40\u0e23\u0e35\u0e22 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 500000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u60c5\u5831\u901a\u4fe1\u30fbit 157  \u0e0b\u0e2d\u0e22 \u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e38\u0e02 58 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569024980\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21.\u0e0b\u0e35. \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024980 \u0e1a\u0e08.\u0e40\u0e04.\u0e40\u0e2d\u0e47\u0e21.\u0e0b\u0e35. \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c  \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5efa\u8a2d 75\/260  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0473569000881\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e21.\u0e44\u0e01\u0e48\u0e44\u0e02\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000881 \u0e2b\u0e08.\u0e17\u0e35.\u0e40\u0e2d\u0e47\u0e21.\u0e44\u0e01\u0e48\u0e44\u0e02\u0e48\u0e40\u0e01\u0e29\u0e15\u0e23\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c 2569-07-04 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e44\u0e01\u0e48\u0e44\u0e02\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569006858\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1f.\u0e1e\u0e35.\u0e40\u0e04. \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"61900\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"61900\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006858 \u0e2b\u0e08.\u0e40\u0e2d\u0e1f.\u0e1e\u0e35.\u0e40\u0e04. \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 2569-07-03 500000 61900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e43\u0e19\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 39\/37  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125921\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125921 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u6559\u80b2 576\/3  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27112(\u0e40\u0e2d\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e21\u0e1a\u0e23\u0e39\u0e13\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126171\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e27\u0e34\u0e23\u0e48\u0e32 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126171 \u0e1a\u0e08.\u0e23\u0e35\u0e27\u0e34\u0e23\u0e48\u0e32 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e01\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e16\u0e32\u0e27\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e01\u0e15\u0e2d\u0e1c\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 6\/7  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e2a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e08\u0e35 \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e04\u0e34\u0e14 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126278\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e19\u0e17\u0e4c\u0e14\u0e34 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63120\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63120\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126278 \u0e1a\u0e08.\u0e40\u0e23\u0e19\u0e17\u0e4c\u0e14\u0e34 \u0e17\u0e35\u0e40\u0e2d\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 63120 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e27\u0e1a\u0e17\u0e48\u0e32 (web portals) \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e08\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e48\u0e32-\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e40\u0e01\u0e47\u0e1a\u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u60c5\u5831\u901a\u4fe1\u30fbit 1333\/14  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e40\u0e14\u0e2d\u0e30\u0e44\u0e25\u0e19\u0e4c\u0e27\u0e07\u0e28\u0e4c\u0e2a\u0e27\u0e48\u0e32\u0e07  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 14 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126359\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e25\u0e21\u0e2d\u0e19\u0e1e\u0e25\u0e35\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0105569126359 \u0e1a\u0e08.\u0e41\u0e0b\u0e25\u0e21\u0e2d\u0e19\u0e1e\u0e25\u0e35\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49, \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07, \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569126430\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e20\u0e32 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126430 \u0e1a\u0e08.\u0e19\u0e20\u0e32 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 846\/93  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 43 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0123569002097\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002097 \u0e2b\u0e08.\u0e27\u0e35.\u0e1e\u0e35.\u0e40\u0e2d\u0e47\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-03 500000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 253\/189  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0145569004393\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e40\u0e21\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004393 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e40\u0e21\u0e23\u0e48\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 253  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0193569000710\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000710 \u0e2b\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-03 500000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e07\u0e32\u0e19) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 123\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035093\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e20\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035093 \u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e20\u0e34\u0e27\u0e31\u0e12\u0e19\u0e4c\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 81\/455  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0213569001162\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e25\u0e14\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001162 \u0e2b\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e25\u0e14\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-03 500000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 789\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006377\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e19\u0e1e\u0e07\u0e28\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33149\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33149\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006377 \u0e1a\u0e08.\u0e1e\u0e19\u0e1e\u0e07\u0e28\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 33149 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e01\u0e49\u0e44\u0e02 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e48\u0e2d\u0e25\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e1b\u0e23\u0e34\u0e07\u0e40\u0e01\u0e2d\u0e23\u0e4c \u88fd\u9020 519  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004339\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e17\u0e35 \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004339 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e17\u0e35 \u0e01\u0e32\u0e23\u0e42\u0e22\u0e18\u0e32 2569-07-03 500000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u5efa\u8a2d 112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015065\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e2d\u0e19\u0e2d\u0e38\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015065 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e2d\u0e19\u0e2d\u0e38\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 55101 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u5bbf\u6cca\u30fb\u98f2\u98df 99\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015090\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e2a\u0e27\u0e35\u0e17\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015090 \u0e1a\u0e08.\u0e17\u0e35\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e2a\u0e27\u0e35\u0e17\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e2d\u0e23\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e02\u0e19\u0e21\u0e40\u0e04\u0e49\u0e01 \u0e04\u0e38\u0e01\u0e01\u0e35\u0e49 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e19\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 555\/85  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0525569001587\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e1b\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47733\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47733\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001587 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e1b\u0e31\u0e49\u0e19\u0e14\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 47733 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e21\u0e49 \u0e40\u0e21\u0e25\u0e47\u0e14\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e38 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0533569000511\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e21\u0e35\u0e19\u0e49\u0e2d\u0e22\u0e2d\u0e34\u0e19\u0e0b\u0e39\u0e40\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43222\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43222\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0533569000511 \u0e2b\u0e08.\u0e2b\u0e21\u0e35\u0e19\u0e49\u0e2d\u0e22\u0e2d\u0e34\u0e19\u0e0b\u0e39\u0e40\u0e25\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-03 500000 43222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e09\u0e19\u0e27\u0e19\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19,\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 160\/189  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0563569000601\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e23\u0e34\u0e0a \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0563569000601 \u0e2b\u0e08.\u0e1e\u0e31\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e23\u0e34\u0e0a \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-03 500000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e21\u0e39 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e16\u0e19\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 200  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0655569002108\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e34\u0e08\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002108 \u0e1a\u0e08.\u0e01\u0e34\u0e08\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19  \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01  \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21  \u0e1a\u0e34\u0e25\u0e14\u0e4c\u0e2d\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u5efa\u8a2d 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0843569001299\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e27\u0e07\u0e28\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47735\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47735\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001299 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e27\u0e07\u0e28\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 2569-07-03 500000 47735 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0905569005261\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e2d\u0e31\u0e1e \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005261 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e2d\u0e31\u0e1e \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 500000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e04\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19  \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569124968\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39 \u0e19\u0e49\u0e2d\u0e15\u0e18\u0e34\u0e07 \u0e1a\u0e31\u0e17 \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124968 \u0e1a\u0e08.\u0e14\u0e39 \u0e19\u0e49\u0e2d\u0e15\u0e18\u0e34\u0e07 \u0e1a\u0e31\u0e17 \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c  \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e0d\u52d5\u7523 96\/181  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 24 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125336\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2a\u0e01\u0e32\u0e22 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79909\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79909\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125336 \u0e1a\u0e08.\u0e14\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2a\u0e01\u0e32\u0e22 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 79909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 9\/40  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125557\",\"name_th\":\"\u0e1a\u0e08.\u0e0d\u0e32\u0e13\u0e34 \u0e0d\u0e32\u0e13\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125557 \u0e1a\u0e08.\u0e0d\u0e32\u0e13\u0e34 \u0e0d\u0e32\u0e13\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/38  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 77 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125654\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e1a\u0e1a\u0e38\u0e0d  \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e18\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125654 \u0e1a\u0e08.\u0e43\u0e1a\u0e1a\u0e38\u0e0d  \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e18\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 78200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 88\/18  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e27\u0e34\u0e19\u0e17\u0e27\u0e07\u0e28\u0e4c 78 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021905\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e42\u0e0b \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021905 \u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e42\u0e0b \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 (battery energy storage system) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 2717  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569020496\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35 \u0e1e\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81292\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81292\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020496 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e08\u0e35 \u0e1e\u0e39\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 81292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 9\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0195569002412\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e01\u0e01\u0e35\u0e49\u0e27\u0e48\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002412 \u0e1a\u0e08.\u0e19\u0e34\u0e01\u0e01\u0e35\u0e49\u0e27\u0e48\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c \u0e43\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e17\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0503569004304\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004304 \u0e2b\u0e08.\u0e27\u0e35\u0e1a\u0e34\u0e25\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-02 500000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 84\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0543569000252\",\"name_th\":\"\u0e2b\u0e08.\u0e22\u0e39 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0543569000252 \u0e2b\u0e08.\u0e22\u0e39 \u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 2569-07-02 500000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e23\u0e35\u0e42\u0e19\u0e40\u0e27\u0e17 \u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 410\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0615569000458\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e31\u0e19\u0e40\u0e14\u0e22\u0e4c \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58192\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58192\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000458 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e0b\u0e31\u0e19\u0e40\u0e14\u0e22\u0e4c \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 58192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e20\u0e32\u0e1e\u0e01\u0e23\u0e32\u0e1f\u0e1f\u0e34\u0e01 \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c  \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 233  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0635569001365\",\"name_th\":\"\u0e1a\u0e08.\u0e2d.\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001365 \u0e1a\u0e08.\u0e2d.\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/4  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0765569001381\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 1986 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001381 \u0e1a\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 1986 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\/\u0e15\u0e48\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e22\u0e37\u0e48\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\/\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e27\u0e14\u0e49\u0e32\u0e27 \u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 186\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0843569001281\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e19\u0e32\u0e20\u0e31\u0e17\u0e23 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49209\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49209\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001281 \u0e2b\u0e08.\u0e0a\u0e19\u0e32\u0e20\u0e31\u0e17\u0e23 \u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 2569-07-02 500000 49209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07 \u904b\u8f38\u30fb\u7269\u6d41 87  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0865569001151\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001151 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 500000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 173  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569006505\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006505 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e08.\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-01 500000 33121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33\u0e14\u0e35 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e1b\u0e31\u0e4a\u0e21\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e42\u0e1a\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 301\/170  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123830\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1f\u0e25\u0e17\u0e4c \u0e40\u0e2d \u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93111\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93111\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123830 \u0e1a\u0e08.\u0e44\u0e1f\u0e25\u0e17\u0e4c \u0e40\u0e2d \u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 93111 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e0b\u0e49\u0e2d\u0e21\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 1161  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e3539 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0123569002071\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e39\u0e01\u0e41\u0e21\u0e48\u0e2a\u0e21\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002071 \u0e2b\u0e08.\u0e25\u0e39\u0e01\u0e41\u0e21\u0e48\u0e2a\u0e21 2569-07-01 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 116  \u0e0b\u0e2d\u0e22 \u0e0b\u0e2d\u0e22\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 8 \u0e41\u0e22\u0e01 20 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024467\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e17\u0e35\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024467 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1e\u0e2d\u0e23\u0e34\u0e17\u0e35\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 93112 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e17\u0e35\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e04\u0e25\u0e31\u0e1a \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e2d\u0e42\u0e23\u0e1a\u0e34\u0e04 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e42\u0e22\u0e04\u0e30 \u0e2f\u0e25\u0e2f \u82b8\u8853\u30fb\u5a2f\u697d 45\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024530\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e40\u0e27\u0e23\u0e19 \u0e40\u0e27\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024530 \u0e1a\u0e08.\u0e42\u0e0b\u0e40\u0e27\u0e23\u0e19 \u0e40\u0e27\u0e19\u0e40\u0e0a\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e02\u0e49\u0e2d\u0e1e\u0e34\u0e1e\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 92\/13  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024581\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e0b\u0e0b\u0e35\u0e48 \u0e42\u0e27\u0e25\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024581 \u0e1a\u0e08.\u0e2d\u0e2d\u0e0b\u0e0b\u0e35\u0e48 \u0e42\u0e27\u0e25\u0e40\u0e17\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 27101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u88fd\u9020 5\/54  \u0e0b\u0e2d\u0e22 \u0e07\u0e32\u0e21\u0e27\u0e07\u0e28\u0e4c\u0e27\u0e32\u0e19 6 \u0e41\u0e22\u0e01 21 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0175569000410\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e15\u0e4c\u0e23\u0e31\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000410 \u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e15\u0e4c\u0e23\u0e31\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 119\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002404\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19-\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c.\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002404 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19-\u0e40\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c.\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 20121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2a\u0e31\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e38\u0e4b\u0e22 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e19\u0e49\u0e33\u0e2a\u0e01\u0e31\u0e14\u0e0a\u0e35\u0e27\u0e20\u0e32\u0e1e \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e01\u0e25\u0e48\u0e38\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 20\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002738\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e31\u0e2a \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c 789\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"30912\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"30912\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002738 \u0e2b\u0e08.\u0e1a\u0e31\u0e2a \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c 789 2569-07-01 500000 30912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e40\u0e04\u0e32\u0e30 \u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e17\u0e33\u0e2a\u0e35 \u0e0b\u0e48\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 47\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003531\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e0a\u0e32 \u0e23\u0e2d\u0e22\u0e31\u0e25\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003531 \u0e1a\u0e08.\u0e04\u0e0a\u0e32 \u0e23\u0e2d\u0e22\u0e31\u0e25\u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e38\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e43\u0e19\u0e23\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e25\u0e30\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e15\u0e4a\u0e30\u0e2a\u0e19\u0e38\u0e4a\u0e01\u0e40\u0e01\u0e2d\u0e23\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08 \u82b8\u8853\u30fb\u5a2f\u697d 99\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0343569001773\",\"name_th\":\"\u0e2b\u0e08.\u0e22\u0e32\u0e22\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1a\u0e23\u0e23\u0e25\u0e37\u0e2d\u0e42\u0e25\u0e01\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001773 \u0e2b\u0e08.\u0e22\u0e32\u0e22\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1a\u0e23\u0e23\u0e25\u0e37\u0e2d\u0e42\u0e25\u0e01 2569-07-01 500000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23  \u0e19\u0e49\u0e33\u0e1b\u0e25\u0e32\u0e23\u0e49\u0e32\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u88fd\u9020 711  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001462\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e27\u0e23\u0e23\u0e18\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001462 \u0e2b\u0e08.\u0e18\u0e19\u0e27\u0e23\u0e23\u0e18\u0e19\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-01 500000 43299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e49\u0e21\u0e19\u0e49\u0e33 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e04\u0e39\u0e48\u0e04\u0e49\u0e32 \u5efa\u8a2d 164  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003386\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e41\u0e15\u0e49\u0e27 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e2d\u0e38\u0e14\u0e23 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003386 \u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e41\u0e15\u0e49\u0e27 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e2d\u0e38\u0e14\u0e23 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e21\u0e39\u0e25\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 315  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e19\u0e32\u0e2b\u0e25\u0e48\u0e33 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0465569000794\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e1a\u0e31\u0e07\u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000794 \u0e1a\u0e08.\u0e2d\u0e32\u0e1a\u0e31\u0e07\u0e42\u0e0a\u0e04\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 195  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e32\u0e21\u0e39\u0e25 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0493569000377\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e40\u0e14\u0e0a \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52214\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52214\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23\",\"province_ja\":\"\u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\",\"search_text\":\"0493569000377 \u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e40\u0e14\u0e0a \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c 2569-07-01 500000 52214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e16\u0e22\u0e01 \u0e23\u0e16\u0e2a\u0e44\u0e25\u0e14\u0e4c \u0e23\u0e16\u0e25\u0e32\u0e01\u0e08\u0e39\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e13\u0e17\u0e35\u0e48 \u0e22\u0e01\u0e23\u0e16\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e23\u0e16\u0e40\u0e2a\u0e35\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e16\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49 \u0e23\u0e16\u0e1b\u0e49\u0e32\u0e22\u0e41\u0e14\u0e07 \u0e23\u0e16\u0e40\u0e01\u0e48\u0e32 \u0e23\u0e16\u0e43\u0e2b\u0e21\u0e48 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e23\u0e16 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e23\u0e16 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e15\u0e48\u0e32\u0e07\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30 \u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 222  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e34\u0e04\u0e21\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c\u0e2b\u0e19\u0e2d\u0e07\u0e41\u0e15\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e21\u0e38\u0e01\u0e14\u0e32\u0e2b\u0e32\u0e23 \u30e0\u30c3\u30af\u30c0\u30fc\u30cf\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569014794\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e17\u0e0a\u0e4c \u0e0a\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014794 \u0e1a\u0e08.\u0e21\u0e34\u0e17\u0e0a\u0e4c \u0e0a\u0e32 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e02\u0e49\u0e32\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e02\u0e49\u0e32\u0e27 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e07\u0e32 \u0e16\u0e31\u0e48\u0e27 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1b\u0e2d \u0e19\u0e38\u0e48\u0e19 \u0e1d\u0e49\u0e32\u0e22 \u0e04\u0e25\u0e31\u0e48\u0e07 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07\u0e44\u0e21\u0e49 \u0e22\u0e32\u0e07 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e2a\u0e34\u0e48\u0e07\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299\/35  \u0e0b\u0e2d\u0e22 27 \u0e2a\u0e35\u0e27\u0e25\u0e35\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e16\u0e19\u0e19\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e2a\u0e21\u0e42\u0e20\u0e0a\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 700 \u0e1b\u0e35 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569014824\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014824 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e2d\u0e1f\u0e1f\u0e35\u0e48 \u0e42\u0e23\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 310  \u0e16\u0e19\u0e19\u0e21\u0e13\u0e35\u0e19\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0575569004284\",\"name_th\":\"\u0e1a\u0e08.\u0e0a.\u0e40\u0e25\u0e34\u0e28\u0e23\u0e2a\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004284 \u0e1a\u0e08.\u0e0a.\u0e40\u0e25\u0e34\u0e28\u0e23\u0e2a\u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e2d\u0e2a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e19\u0e49\u0e33\u0e08\u0e34\u0e49\u0e21 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e0b\u0e38\u0e1b \u0e2b\u0e21\u0e48\u0e32\u0e25\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 121\/29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569001896\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001896 \u0e1a\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e49\u0e32\u0e19\u0e02\u0e19\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 340\/16  \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0705569003006\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e21\u0e17\u0e2d\u0e07 \u0e28\u0e23\u0e35\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e2d\u0e49\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003006 \u0e1a\u0e08.\u0e40\u0e08\u0e35\u0e22\u0e21\u0e17\u0e2d\u0e07 \u0e28\u0e23\u0e35\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e2d\u0e49\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e44\u0e02\u0e48\u0e44\u0e01\u0e48 \u0e44\u0e02\u0e48\u0e40\u0e1b\u0e47\u0e14 \u0e44\u0e02\u0e48\u0e19\u0e01\u0e01\u0e23\u0e30\u0e17\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e44\u0e02\u0e48\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e44\u0e02\u0e48\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1b\u0e28\u0e38\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/24  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e2b\u0e31\u0e01 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0805569002467\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e34\u0e48\u0e19\u0e1e\u0e25\u0e2d\u0e22 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002467 \u0e1a\u0e08.\u0e1b\u0e34\u0e48\u0e19\u0e1e\u0e25\u0e2d\u0e22 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e27\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 189\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002475\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e01\u0e19\u0e01 2026  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002475 \u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e01\u0e19\u0e01 2026  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1648  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0845569009992\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 88 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569009992 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 88 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e2d\u0e23\u0e4c\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 185\/99  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e14\u0e42\u0e1e\u0e18\u0e34\u0e4c-\u0e1a\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0863569000390\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2d\u0e48\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e1c\u0e21\u0e22\u0e32\u0e27\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0863569000390 \u0e2b\u0e08.\u0e44\u0e2d\u0e48\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e1c\u0e21\u0e22\u0e32\u0e27 2569-07-01 500000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 112\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0905569005112\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":500000,\"capital_display\":\"500,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005112 \u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 500000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 85  \u0e0b\u0e2d\u0e22 \u0e23\u0e2a\u0e27\u0e23\u0e23\u0e13 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0805569002815\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e17\u0e18\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":450000,\"capital_display\":\"450,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002815 \u0e1a\u0e08.\u0e1e\u0e31\u0e17\u0e18\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 450000 47524 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e23\u0e32\u0e22 \u0e01\u0e23\u0e27\u0e14 \u0e2d\u0e34\u0e10 \u0e2b\u0e34\u0e19 \u0e1b\u0e39\u0e19\u0e0b\u0e35\u0e40\u0e21\u0e19\u0e15\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 307  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002823\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e34\u0e48\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e25\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":450000,\"capital_display\":\"450,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002823 \u0e1a\u0e08.\u0e22\u0e34\u0e48\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e01\u0e25\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 450000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e14\u0e34\u0e19 \u0e14\u0e34\u0e19\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e17\u0e23\u0e32\u0e22 \u0e01\u0e23\u0e27\u0e14 \u0e2d\u0e34\u0e10 \u0e2b\u0e34\u0e19\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0473569000989\",\"name_th\":\"\u0e2b\u0e08.\u0e0a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":450000,\"capital_display\":\"450,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000989 \u0e2b\u0e08.\u0e0a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-20 450000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0203569002924\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e17\u0e35\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":450000,\"capital_display\":\"450,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002924 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35\u0e17\u0e35\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-08 450000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33 \u904b\u8f38\u30fb\u7269\u6d41 50\/20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0903569001638\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e32\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":410000,\"capital_display\":\"410,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001638 \u0e2b\u0e08.\u0e1f\u0e32\u0e40\u0e17\u0e35\u0e22\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-15 410000 49323 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e32\u0e22\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u904b\u8f38\u30fb\u7269\u6d41 23  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e01\u0e32\u0e2c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569143130\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e01\u0e01\u0e34\u0e27\u0e25\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143130 \u0e1a\u0e08.\u0e40\u0e23\u0e01\u0e01\u0e34\u0e27\u0e25\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 400000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e02\u0e35\u0e22\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34 (licensing) \u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 99\/115  \u0e16\u0e19\u0e19\u0e04\u0e23\u0e38\u0e43\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0933569000330\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e1a\u0e32\u0e23\u0e2d\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30eb\u30f3\u770c\",\"search_text\":\"0933569000330 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e1a\u0e32\u0e23\u0e2d\u0e01\u0e2a\u0e4c 2569-07-28 400000 14111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u88fd\u9020 125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e31\u0e17\u0e25\u0e38\u0e07 \u30d1\u30c3\u30bf\u30eb\u30f3\u770c\"},{\"reg_no\":\"0105569141269\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35.\u0e14\u0e23\u0e32\u0e22\u0e44\u0e2d\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141269 \u0e1a\u0e08.\u0e27\u0e35.\u0e14\u0e23\u0e32\u0e22\u0e44\u0e2d\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 400000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07\u0e41\u0e2b\u0e49\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 282\/253  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e04 \u0e1e\u0e32\u0e23\u0e4c\u0e042 (\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e0b\u0e32\u0e1f\u0e32\u0e23\u0e35\u0e40\u0e27\u0e34\u0e25\u0e14\u0e4c) \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0503569005238\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005238 \u0e2b\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-25 400000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569005246\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e25\u0e49\u0e33\u0e1f\u0e49\u0e32\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005246 \u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e25\u0e49\u0e33\u0e1f\u0e49\u0e32\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-25 400000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 52  \u0e0b\u0e2d\u0e22 7 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e25\u0e49\u0e32\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0443569000890\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32303\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32303\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000890 \u0e2b\u0e08.\u0e17\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 2569-07-24 400000 32303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e1b\u0e25\u0e32 \u0e40\u0e1a\u0e47\u0e14 \u0e40\u0e2b\u0e22\u0e37\u0e48\u0e2d\u0e1b\u0e25\u0e2d\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 301  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0805569002904\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e21\u0e32\u0e0a\u0e47\u0e2d\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002904 \u0e1a\u0e08.\u0e21\u0e32\u0e21\u0e32\u0e0a\u0e47\u0e2d\u0e1b 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 400000 47190 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39  \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 4 \u0e02\u0e27\u0e32 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0413569001713\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e19\u0e32\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e15\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001713 \u0e2b\u0e08.\u0e19\u0e32\u0e19\u0e32\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e15 2569-07-23 400000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0a\u0e33\u0e23\u0e30\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d              \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e34\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 140\/94  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e23\u0e16\u0e44\u0e1f \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0123569002267\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e19\u0e17\u0e4c \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\u0e19\u0e49\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002267 \u0e2b\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e19\u0e19\u0e17\u0e4c \u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\u0e19\u0e49\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 2569-07-22 400000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24  \u0e0b\u0e2d\u0e22 \u0e40\u0e23\u0e27\u0e14\u0e35 18 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0653569001193\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e23\u0e30\u0e08\u0e01\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e14\u0e34\u0e19 \u0e0a\u0e48\u0e32\u0e07\u0e1a\u0e2d\u0e25\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001193 \u0e2b\u0e08.\u0e01\u0e23\u0e30\u0e08\u0e01\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e14\u0e34\u0e19 \u0e0a\u0e48\u0e32\u0e07\u0e1a\u0e2d\u0e25 2569-07-22 400000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u5efa\u8a2d 12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0103569007781\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e27\u0e32\u0e22 \u0e44\u0e1f\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e17\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007781 \u0e2b\u0e08.\u0e17\u0e35\u0e27\u0e32\u0e22 \u0e44\u0e1f\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e17\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-20 400000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e44\u0e1f\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 178\/70  \u0e16\u0e19\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133819\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25 \u0e40\u0e2d\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93199\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93199\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133819 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25 \u0e40\u0e2d\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 400000 93199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e1f\u0e38\u0e15\u0e0b\u0e2d\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e01\u0e48\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e01\u0e35\u0e2c\u0e32  \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e23\u0e32\u0e22\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u82b8\u8853\u30fb\u5a2f\u697d 582  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0545569000785\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e01\u0e35\u0e48\u0e40\u0e20\u0e2a\u0e31\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e41\u0e1e\u0e23\u0e48\",\"province_ja\":\"\u30d7\u30ec\u30fc\u770c\",\"search_text\":\"0545569000785 \u0e1a\u0e08.\u0e44\u0e2e\u0e01\u0e35\u0e48\u0e40\u0e20\u0e2a\u0e31\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 400000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 112\/3-112\/5  \u0e16\u0e19\u0e19\u0e0a\u0e48\u0e2d\u0e41\u0e2e \u0e08.\u0e41\u0e1e\u0e23\u0e48 \u30d7\u30ec\u30fc\u770c\"},{\"reg_no\":\"0635569001454\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e2a \u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001454 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e2a \u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 400000 77301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 272\/42  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e1e\u0e32\u0e19\u0e34\u0e0a \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0133569002381\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e34\u0e01\u0e01\u0e35\u0e49\u0e41\u0e17\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95220\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95220\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002381 \u0e2b\u0e08.\u0e23\u0e34\u0e01\u0e01\u0e35\u0e49\u0e41\u0e17\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a 2569-07-11 400000 95220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2d\u0e31\u0e14\u0e09\u0e35\u0e14 \u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e22\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e19\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e32\u0e41\u0e01\u0e4a\u0e2a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 59\/478  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e04\u0e25\u0e2d\u0e07 7 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569129846\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e13\u0e31\u0e19\u0e0a\u0e34\u0e14\u0e32 36 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129846 \u0e1a\u0e08.\u0e0a\u0e13\u0e31\u0e19\u0e0a\u0e34\u0e14\u0e32 36 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 400000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 280  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130470\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130470 \u0e1a\u0e08.\u0e04\u0e35\u0e22\u0e4c\u0e2a\u0e42\u0e15\u0e19 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 400000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e0d\u52d5\u7523 294  \u0e0b\u0e2d\u0e22 \u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 \u0e16\u0e19\u0e19\u0e17\u0e48\u0e32\u0e02\u0e49\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0325569001180\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23 \u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001180 \u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23 \u0e1e\u0e37\u0e0a\u0e1c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 400000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e18\u0e31\u0e0d\u0e1e\u0e37\u0e0a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 203  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0573569002069\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e01\u0e34\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002069 \u0e2b\u0e08.\u0e19\u0e23\u0e32\u0e27\u0e34\u0e0a\u0e0d\u0e4c \u0e01\u0e34\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-07 400000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 70\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0135569020593\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e19\u0e32\u0e27\u0e32\u0e19\u0e32 \u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020593 \u0e1a\u0e08.\u0e1e\u0e32\u0e19\u0e32\u0e27\u0e32\u0e19\u0e32 \u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 400000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/177  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569123848\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e0b\u0e14\u0e27\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123848 \u0e1a\u0e08.\u0e41\u0e0b\u0e14\u0e27\u0e35 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 400000 70209 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 marketplace (shopee, lazada, tiktok shop) \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e41\u0e25\u0e30 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e22\u0e38\u0e04\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 165\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e27\u0e19\u0e0a\u0e37\u0e48\u0e19\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e19\u0e2d\u0e23\u0e4c\u0e17\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e0b\u0e2d\u0e22 \u0e04\u0e39\u0e49\u0e1a\u0e2d\u0e19 27 \u0e41\u0e22\u0e01 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0503569004282\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e21\u0e1e\u0e32\u0e25\u0e48\u0e32 \u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":400000,\"capital_display\":\"400,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004282 \u0e2b\u0e08.\u0e2d\u0e34\u0e21\u0e1e\u0e32\u0e25\u0e48\u0e32 \u0e41\u0e21\u0e19\u0e0a\u0e31\u0e48\u0e19 2569-07-01 400000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u4e0d\u52d5\u7523 79  \u0e16\u0e19\u0e19\u0e0a\u0e49\u0e32\u0e07\u0e40\u0e1c\u0e37\u0e2d\u0e01 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569127355\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e15\u0e47\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":360000,\"capital_display\":\"360,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127355 \u0e1a\u0e08.\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e15\u0e47\u0e21\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 360000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e02\u0e2d\u0e07\u0e2b\u0e27\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 119  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e40\u0e01\u0e49\u0e3251 (\u0e16\u0e19\u0e19\u0e40\u0e2a\u0e23\u0e356) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0903569001891\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 69\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001891 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 69 2569-07-30 350000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/7  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e07\u0e32\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569139744\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c 13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139744 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c 13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 350000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 159\/187  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e1f\u0e4c \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01\u0e1a\u0e39\u0e40\u0e25\u0e2d\u0e27\u0e32\u0e23\u0e4c\u0e14 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e219 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007854\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e2d\u0e21 \u0e17\u0e39 \u0e40\u0e1a\u0e1a\u0e35\u0e49\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007854 \u0e2b\u0e08.\u0e21\u0e2d\u0e21 \u0e17\u0e39 \u0e40\u0e1a\u0e1a\u0e35\u0e49 2569-07-21 350000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e43\u0e19\u0e04\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e22\u0e38\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e21\u0e48\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e0a\u0e38\u0e14\u0e04\u0e25\u0e38\u0e21\u0e17\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e21\u0e48\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e43\u0e2b\u0e49\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/288  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07164 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007706\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e2d\u0e21 \u0e17\u0e39 \u0e21\u0e2d\u0e21\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007706 \u0e2b\u0e08.\u0e21\u0e2d\u0e21 \u0e17\u0e39 \u0e21\u0e2d\u0e21 2569-07-17 350000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e4d\u0e32\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e43\u0e19\u0e04\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e1e\u0e22\u0e38\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e21\u0e48\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e0a\u0e38\u0e14\u0e04\u0e25\u0e38\u0e21\u0e17\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e41\u0e21\u0e48\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e43\u0e2b\u0e49\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 68\/288  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 164 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0553569000422\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 999 \u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0553569000422 \u0e2b\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 999 \u0e1f\u0e39\u0e49\u0e14 2569-07-15 350000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e32\u0e01\u0e33\u0e44\u0e23\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 72\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002348\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002348 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e35 \u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-09 350000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 42\/132  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001492\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48\u0e2e\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e4c\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001492 \u0e2b\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48\u0e2e\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e4c\u0e14 2569-07-08 350000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1a\u0e31\u0e15\u0e23\u0e01\u0e34\u0e4a\u0e1f\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e42\u0e0b\u0e40\u0e0b\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u60c5\u5831\u901a\u4fe1\u30fbit 58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0503569004312\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":350000,\"capital_display\":\"350,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004312 \u0e2b\u0e08.\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 2569-07-02 350000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/247  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0635569001527\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e0b\u0e35\u0e27\u0e32\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":301000,\"capital_display\":\"301,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001527 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e0b\u0e35\u0e27\u0e32\u0e22 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 301000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e22\u0e32\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e19 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40\/70  \u0e16\u0e19\u0e19\u0e41\u0e21\u0e48\u0e2a\u0e2d\u0e14-\u0e41\u0e21\u0e48\u0e15\u0e32\u0e27 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0743569000927\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e41\u0e2d\u0e25.\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":300500,\"capital_display\":\"300,500 \u0e1a\u0e32\u0e17\",\"objective_code\":\"27330\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"27330\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000927 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e41\u0e2d\u0e25.\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c 2569-07-07 300500 27330 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e32\u0e22\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e2a\u0e32\u0e25\u0e48\u0e2d\u0e1f\u0e49\u0e32 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 172\/136  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e19\u0e0b\u0e35\u0e42\u0e2d\u0e04\u0e23\u0e34\u0e1b \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 81 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569143458\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e39\u0e13\u0e2a\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143458 \u0e1a\u0e08.\u0e04\u0e39\u0e13\u0e2a\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 300000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e22\u0e37\u0e48\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 105\/281  \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569003351\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e14\u0e34\u0e25\u0e01\u0e01\u0e38\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003351 \u0e2b\u0e08.\u0e40\u0e25\u0e34\u0e28\u0e14\u0e34\u0e25\u0e01\u0e01\u0e38\u0e25 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-31 300000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 93\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569003360\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e40\u0e21\u0e18\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003360 \u0e2b\u0e08.\u0e18\u0e19\u0e40\u0e21\u0e18\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-31 300000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 93\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0535569000823\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000823 \u0e1a\u0e08.\u0e2d\u0e31\u0e19 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 300000 46201 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e16\u0e31\u0e48\u0e27\u0e40\u0e02\u0e35\u0e22\u0e27 \u0e16\u0e31\u0e4b\u0e27\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e21\u0e30\u0e1e\u0e23\u0e49\u0e32\u0e27\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0903569001883\",\"name_th\":\"\u0e2b\u0e08.  \u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001883 \u0e2b\u0e08.  \u0e40\u0e2d\u0e47\u0e19\u0e0b\u0e35\u0e1f\u0e39\u0e49\u0e14\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-30 300000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 171  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569008150\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a 2026\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008150 \u0e2b\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d\u0e2a 2026 2569-07-27 300000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e17\u0e33\u0e27\u0e34\u0e08\u0e31\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/279  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024874\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e08\u0e23\u0e34\u0e07\u0e23\u0e27\u0e22\u0e25\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024874 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e08\u0e23\u0e34\u0e07\u0e23\u0e27\u0e22\u0e25\u0e49\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 300000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 98\/110  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569023215\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e17\u0e35\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01611\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01611\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023215 \u0e1a\u0e08.\u0e17\u0e35 \u0e17\u0e35\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 300000 01611 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e01\u0e4d\u0e32\u0e08\u0e31\u0e14 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e1b\u0e25\u0e27\u0e01 \u0e41\u0e21\u0e25\u0e07 \u0e22\u0e38\u0e07 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e32\u0e2b\u0e30\u0e19\u0e4d\u0e32\u0e42\u0e23\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e4d\u0e32\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e27\u0e01 \u0e41\u0e21\u0e25\u0e07\u0e22\u0e38\u0e07 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e32\u0e2b\u0e30\u0e19\u0e4d\u0e32\u0e42\u0e23\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u8fb2\u6797\u6c34\u7523 100\/128  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0175569000509\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0175569000509 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 300000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 290\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e1a\u0e38\u0e23\u0e35 \u30b7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0193569000841\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52241\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52241\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000841 \u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e23\u0e34\u0e0a \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-27 300000 52241 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e25\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e08\u0e32\u0e01\u0e15\u0e39\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 59  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569004082\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e14\u0e17\u0e2a\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004082 \u0e1a\u0e08.\u0e41\u0e14\u0e17\u0e2a\u0e4c \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 300000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e25\u0e30\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c  \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e2d\u0e19\u0e44\u0e0b\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u88fd\u9020 85\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0505569016754\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e21\u0e31\u0e27\u0e23\u0e4c \u0e40\u0e14\u0e2d \u0e40\u0e0c\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10772\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10772\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016754 \u0e1a\u0e08.\u0e25\u0e32\u0e21\u0e31\u0e27\u0e23\u0e4c \u0e40\u0e14\u0e2d \u0e40\u0e0c\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 300000 10772 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 69\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569141196\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e14\u0e35 \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141196 \u0e1a\u0e08.\u0e14\u0e47\u0e2d\u0e01\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e14\u0e35 \u0e42\u0e04\u0e42\u0e04\u0e19\u0e31\u0e15  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 300000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e3034 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e18\u0e34\u0e2a\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140301\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32 \u0e0a\u0e47\u0e2d\u0e1b 199 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140301 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32 \u0e0a\u0e47\u0e2d\u0e1b 199 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 300000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 479\/468  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024653\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024653 \u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e0d\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 300000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 390\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0455569001570\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e01\u0e23 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e2d\u0e2d\u0e1b\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0455569001570 \u0e1a\u0e08.\u0e18\u0e19\u0e32\u0e01\u0e23 \u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e2d\u0e2d\u0e1b\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 300000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14            (\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u60c5\u5831\u901a\u4fe1\u30fbit 9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569138934\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138934 \u0e1a\u0e08.\u0e44\u0e14\u0e21\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 300000 70209 \u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e02\u0e32\u0e22\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 69\/29  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e34\u0e19 24\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0195569002676\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e19\u0e17\u0e34\u0e19\u0e48\u0e32 \u0e42\u0e2e\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002676 \u0e1a\u0e08.\u0e40\u0e08\u0e19\u0e17\u0e34\u0e19\u0e48\u0e32 \u0e42\u0e2e\u0e21\u0e2a\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 300000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e42\u0e2d\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 50\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002826\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002826 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e08 \u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 2569-07-22 300000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u5efa\u8a2d 175\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0135569022472\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e42\u0e17\u0e23\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46439\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46439\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022472 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e42\u0e17\u0e23\u0e1f\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 300000 46439 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e16\u0e49\u0e27\u0e22\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25,\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25,\u0e42\u0e25\u0e48\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/11   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a4 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e40\u0e01\u0e23\u0e13\u0e32\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016444\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e14\u0e35\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016444 \u0e1a\u0e08.\u0e14\u0e39\u0e14\u0e35\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 300000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e16\u0e48\u0e32\u0e22\u0e40\u0e17 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 25\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0705569003316\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e39\u0e25\u0e1f\u0e34\u0e25 \u0e42\u0e2e\u0e21 \u0e42\u0e21\u0e14\u0e39\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16220\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16220\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003316 \u0e1a\u0e08.\u0e1f\u0e39\u0e25\u0e1f\u0e34\u0e25 \u0e42\u0e2e\u0e21 \u0e42\u0e21\u0e14\u0e39\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 300000 16220 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 139\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0803569001043\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 2247\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001043 \u0e2b\u0e08.\u0e19\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 2247 2569-07-21 300000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32-\u0e02\u0e32\u0e22\u0e44\u0e1b-\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0805569002785\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e32\u0e21\u0e34\u0e25 \u0e0a\u0e47\u0e2d\u0e1b29 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0805569002785 \u0e1a\u0e08.\u0e22\u0e32\u0e21\u0e34\u0e25 \u0e0a\u0e47\u0e2d\u0e1b29 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 300000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 59\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569136150\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136150 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e23 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 300000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 61\/21  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 45 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027342\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e40\u0e17\u0e01\u0e0b\u0e4c\u0e1a\u0e38\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027342 \u0e1a\u0e08.\u0e42\u0e1b\u0e23 \u0e40\u0e17\u0e01\u0e0b\u0e4c\u0e1a\u0e38\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 300000 58111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e29 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e1a\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e27\u0e13 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e15\u0e39\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 117\/38  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 9\/1 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569007354\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e2d\u0e21\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007354 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e44\u0e2d\u0e21\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 300000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e04\u0e2a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 110\/123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0135569022154\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e22\u0e2d\u0e23\u0e21\u0e31\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022154 \u0e1a\u0e08.\u0e40\u0e22\u0e2d\u0e23\u0e21\u0e31\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 300000 85499 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28(\u0e40\u0e22\u0e2d\u0e23\u0e21\u0e31\u0e19) \u6559\u80b2 90\/182  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e10\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e1a\u0e07\u0e01\u0e0a 7 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e2d\u0e07 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000857\",\"name_th\":\"\u0e2b\u0e08.\u0e2e\u0e32\u0e42\u0e15\u0e23\u0e34 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000857 \u0e2b\u0e08.\u0e2e\u0e32\u0e42\u0e15\u0e23\u0e34 \u0e1b\u0e34\u0e42\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22\u0e21 2569-07-18 300000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e31\u0e4a\u0e21\u0e19\u0e4d\u0e49\u0e32\u0e21\u0e31\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e4d\u0e49\u0e32\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0503569005025\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c\u0e0a\u0e34\u0e1b\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005025 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c\u0e0a\u0e34\u0e1b 2569-07-17 300000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e17\u0e33\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e15\u0e49\u0e32\u0e27 \u0e02\u0e2d\u0e27\u0e35\u0e0a\u0e48\u0e32\u0e41\u0e23\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e15\u0e49\u0e32\u0e27 \u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e34\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e41\u0e08\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e08\u0e49\u0e07\u0e2d\u0e2d\u0e01\u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e35\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 99\/109  \u0e0b\u0e2d\u0e22 22 \u0e16\u0e19\u0e19\u0e42\u0e0b\u0e15\u0e19\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0605569002116\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e2b\u0e21\u0e27\u0e22 \u0e41\u0e0b\u0e25\u0e21\u0e48\u0e2d\u0e19\u0e14\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002116 \u0e1a\u0e08.\u0e2d\u0e32\u0e2b\u0e21\u0e27\u0e22 \u0e41\u0e0b\u0e25\u0e21\u0e48\u0e2d\u0e19\u0e14\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 300000 10799 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e14\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e19\u0e49\u0e33\u0e1e\u0e23\u0e34\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u88fd\u9020 96\/57  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0635569001471\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21 \u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0635569001471 \u0e1a\u0e08.\u0e2a\u0e21 \u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 300000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2b\u0e21\u0e27\u0e01 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e0a\u0e31\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0843569001400\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e23\u0e19\u0e34\u0e20\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001400 \u0e2b\u0e08.\u0e1e\u0e23\u0e23\u0e19\u0e34\u0e20\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c 2569-07-17 300000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e19\u0e47\u0e2d\u0e04\u0e14\u0e32\u0e27\u0e19\u0e4c \u5efa\u8a2d 36\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2f \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0143569001201\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e47\u0e19.\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001201 \u0e2b\u0e08.\u0e40\u0e2d.\u0e40\u0e2d\u0e47\u0e19.\u0e40\u0e2d\u0e47\u0e19.\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-16 300000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b\u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c  \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 169\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0503569004991\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e31\u0e19\u0e15\u0e19\u0e32\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004991 \u0e2b\u0e08.\u0e15\u0e31\u0e19\u0e15\u0e19\u0e32 2569-07-16 300000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e1f\u0e25\u0e15 \u0e17\u0e32\u0e27\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16 \u4e0d\u52d5\u7523 1  \u0e0b\u0e2d\u0e22 \u0e17\u0e32\u0e19\u0e15\u0e30\u0e27\u0e31\u0e19 \u0e16\u0e19\u0e19\u0e40\u0e27\u0e35\u0e22\u0e07\u0e1a\u0e31\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569002212\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43301\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43301\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002212 \u0e2b\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2d\u0e34\u0e19\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22 2569-07-16 300000 43301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 978  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569002078\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e42\u0e20\u0e04 768 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20210\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20210\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002078 \u0e1a\u0e08.\u0e18\u0e19\u0e42\u0e20\u0e04 768 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 300000 20210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e21\u0e35\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u88fd\u9020 999\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0815569002122\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e21\u0e31\u0e07\u0e01\u0e238 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002122 \u0e1a\u0e08.\u0e01\u0e49\u0e32\u0e27\u0e21\u0e31\u0e07\u0e01\u0e238 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 300000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 69\/13  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0105569132731\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e35\u0e0a\u0e25\u0e17\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132731 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e35\u0e0a\u0e25\u0e17\u0e34\u0e28 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 300000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e38\u0e4a\u0e01\u0e15\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e2f\u0e25\u0e2f \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e1a\u0e39\u0e18 \u0e2a\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21  \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 738  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e2d\u0e14\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133053\",\"name_th\":\"\u0e1a\u0e08.888 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e44\u0e17\u0e22 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133053 \u0e1a\u0e08.888 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e44\u0e17\u0e22 \u0e1f\u0e23\u0e38\u0e4a\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 300000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 340\/173   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 101 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e14\u0e40\u0e27\u0e2c\u0e38\u0e27\u0e19\u0e32\u0e23\u0e32\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133347\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17  \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64991\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64991\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133347 \u0e1a\u0e08.\u0e44\u0e2d \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17  \u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 300000 64991 \u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e32\u0e22\u0e42\u0e17\u0e40\u0e04\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e0e\u0e40\u0e01\u0e13\u0e11\u0e4c \u0e43\u0e14 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e01\u0e33\u0e01\u0e31\u0e1a\u0e25\u0e2b\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e32\u0e22\u0e42\u0e17\u0e40\u0e04\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 51  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0133569002453\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e21\u0e41\u0e1b\u0e23\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002453 \u0e2b\u0e08.\u0e41\u0e2d\u0e21\u0e41\u0e1b\u0e23\u0e4c \u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e34\u0e04 2569-07-14 300000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell)  \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 234\/429  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0225569002217\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002217 \u0e1a\u0e08.\u0e2a\u0e21\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 300000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1c\u0e31\u0e01\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 140  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0413569001624\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001624 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 2569-07-14 300000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569004851\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e19\u0e01 \u0e41\u0e01\u0e4a\u0e2a\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47735\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47735\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004851 \u0e2b\u0e08.\u0e01\u0e19\u0e01 \u0e41\u0e01\u0e4a\u0e2a\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e2a\u0e4c 2569-07-14 300000 47735 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e01\u0e4a\u0e2a\u0e2b\u0e38\u0e07\u0e15\u0e49\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e01\u0e4a\u0e2a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569132359\",\"name_th\":\"\u0e1a\u0e08. \u0e08\u0e34\u0e15\u0e15\u0e30 \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132359 \u0e1a\u0e08. \u0e08\u0e34\u0e15\u0e15\u0e30 \u0e44\u0e25\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 300000 47593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e21\u0e44\u0e1f \u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 492  \u0e0b\u0e2d\u0e22 \u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c 32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0403569003082\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e43\u0e08\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003082 \u0e2b\u0e08.\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e43\u0e08 2569-07-13 300000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 2\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 0 \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0753569000099\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e25\u0e25\u0e2d\u0e19\u0e23\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\",\"search_text\":\"0753569000099 \u0e2b\u0e08.\u0e41\u0e01\u0e25\u0e25\u0e2d\u0e19\u0e23\u0e35 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 2569-07-13 300000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e21\u0e47\u0e14\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e20\u0e32\u0e1e\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u30b5\u30e0\u30c3\u30c8\u30bd\u30f3\u30af\u30e9\u30fc\u30e0\u770c\"},{\"reg_no\":\"0903569001603\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e41\u0e21\u0e48\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001603 \u0e2b\u0e08.\u0e40\u0e08\u0e49\u0e32\u0e41\u0e21\u0e48\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 2569-07-12 300000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/7  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e07\u0e32\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007391\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e33\u0e23\u0e2d\u0e07 \u0e42\u0e0a\u0e15\u0e34\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47712\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47712\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007391 \u0e2b\u0e08.\u0e08\u0e33\u0e23\u0e2d\u0e07 \u0e42\u0e0a\u0e15\u0e34 2569-07-11 300000 47712 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 117\/130  \u0e0b\u0e2d\u0e22 \u0e23\u0e48\u0e27\u0e21\u0e21\u0e34\u0e15\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e16\u0e19\u0e19\u0e41\u0e22\u0e014\u0e41\u0e02\u0e27\u0e49\u0e07\u0e17\u0e48\u0e32\u0e41\u0e23\u0e49\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0473569000911\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e33\u0e1b\u0e31\u0e19\u0e42\u0e22 \u0e01\u0e35\u0e2c\u0e32\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000911 \u0e2b\u0e08.\u0e04\u0e33\u0e1b\u0e31\u0e19\u0e42\u0e22 \u0e01\u0e35\u0e2c\u0e32 2569-07-11 300000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 102  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569036529\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036529 \u0e1a\u0e08.\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 300000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 47\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e1b\u0e23\u0e30\u0e22\u0e39\u0e23 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009203\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e0a\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009203 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e0a\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 300000 56101 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 76\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0313569001048\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e1e\u0e35 2026\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001048 \u0e2b\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e2a\u0e1e\u0e35 2026 2569-07-10 300000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 266\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0503569004592\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2d\u0e25\u0e14\u0e32\u0e41\u0e27\u0e19\u0e17\u0e31\u0e27\u0e23\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004592 \u0e2b\u0e08.\u0e44\u0e2d\u0e25\u0e14\u0e32\u0e41\u0e27\u0e19\u0e17\u0e31\u0e27\u0e23\u0e4c 2569-07-10 300000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e17\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e16\u0e15\u0e39\u0e49 \u0e23\u0e16\u0e1a\u0e31\u0e2a \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 126  \u0e16\u0e19\u0e19\u0e15\u0e49\u0e19\u0e02\u0e32\u0e21 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0803569000951\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e21\u0e39\u0e40\u0e25\u0e47\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000951 \u0e2b\u0e08.\u0e2d\u0e21\u0e39\u0e40\u0e25\u0e47\u0e17 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 2569-07-10 300000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e48\u0e32\u0e22\u0e01\u0e32\u0e22 \u0e40\u0e02\u0e47\u0e21\u0e01\u0e25\u0e31\u0e14\u0e04\u0e19\u0e17\u0e49\u0e2d\u0e07 \u0e2a\u0e23\u0e49\u0e2d\u0e22\u0e04\u0e2d \u0e08\u0e35\u0e49\u0e1e\u0e23\u0e30 \u0e41\u0e2b\u0e27\u0e19 \u0e01\u0e33\u0e44\u0e25 \u0e08\u0e35\u0e49\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e2a\u0e32\u0e22 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2e\u0e27\u0e07\u0e08\u0e38\u0e49\u0e22 \u0e23\u0e39\u0e1b\u0e1b\u0e31\u0e49\u0e19\u0e1e\u0e23\u0e30 \u0e08\u0e35\u0e49\u0e1e\u0e23\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e40\u0e19\u0e47\u0e15\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 15\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0903569001557\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35 \u0e17\u0e35 \u0e40\u0e1f\u0e23\u0e0a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001557 \u0e2b\u0e08.\u0e1e\u0e35 \u0e17\u0e35 \u0e40\u0e1f\u0e23\u0e0a \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-10 300000 46101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/104\/1  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e30\u0e40\u0e01\u0e29 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0945569000714\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e2a\u0e21\u0e32\u0e27\u0e32\u0e19\u0e35\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47300\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47300\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000714 \u0e1a\u0e08.\u0e2d\u0e31\u0e2a\u0e21\u0e32\u0e27\u0e32\u0e19\u0e35\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 300000 47300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e01\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7\/12  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569129986\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07\u0e27\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129986 \u0e1a\u0e08.\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07\u0e27\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 300000 25999 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e1d\u0e32\u0e02\u0e27\u0e14\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u88fd\u9020 372  \u0e0b\u0e2d\u0e22 \u0e19\u0e32\u0e17\u0e2d\u0e07 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569021166\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e0a\u0e31\u0e22 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021166 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e0a\u0e31\u0e22 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 300000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0465569000867\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e2d\u0e23\u0e4c \u0e14\u0e31\u0e01\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000867 \u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e2d\u0e23\u0e4c \u0e14\u0e31\u0e01\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 300000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e25\u0e21  (air duct) \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5efa\u8a2d 51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0503569004541\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004541 \u0e2b\u0e08.\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 2569-07-09 300000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 36\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0615569000555\",\"name_th\":\"\u0e1a\u0e08.\u0e27.\u0e0a\u0e32\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000555 \u0e1a\u0e08.\u0e27.\u0e0a\u0e32\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 300000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0715569002557\",\"name_th\":\"\u0e1a\u0e08.4\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e1a\u0e1a\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002557 \u0e1a\u0e08.4\u0e40\u0e2d\u0e47\u0e21 \u0e40\u0e1a\u0e1a\u0e35\u0e49 \u0e0a\u0e47\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 300000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e48\u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e14\u0e47\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32  \u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 357\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006951\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e14\u0e14\u0e14\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006951 \u0e1a\u0e08.\u0e41\u0e14\u0e14\u0e14\u0e35 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e22\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 300000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c) \u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e04\u0e27\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 200  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0903569001514\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e44\u0e2d\u0e17\u0e35\u0e40\u0e2d \u0e40\u0e01\u0e21\u0e41\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93293\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93293\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001514 \u0e2b\u0e08.\u0e17\u0e35\u0e44\u0e2d\u0e17\u0e35\u0e40\u0e2d \u0e40\u0e01\u0e21\u0e41\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 2569-07-09 300000 93293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e01\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e40\u0e01\u0e21 (\u0e44\u0e2d\u0e40\u0e17\u0e21) \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a \u0e40\u0e04\u0e23\u0e14\u0e34\u0e15\u0e40\u0e01\u0e21 \u82b8\u8853\u30fb\u5a2f\u697d 9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001522\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07898\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001522 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07898 2569-07-09 300000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/15  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e1e\u0e23\u0e38 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0903569001506\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e31\u0e2a\u0e15\u0e23\u0e32\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001506 \u0e2b\u0e08.\u0e1e\u0e31\u0e2a\u0e15\u0e23\u0e32\u0e1f\u0e39\u0e49\u0e14 2569-07-08 300000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/104\/1  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e30\u0e40\u0e01\u0e29 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569128017\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04\u0e40\u0e0b\u0e19\u0e17\u0e23\u0e34\u0e04 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128017 \u0e1a\u0e08.\u0e2d\u0e35\u0e42\u0e04\u0e40\u0e0b\u0e19\u0e17\u0e23\u0e34\u0e04 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 300000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e31\u0e01\u0e25\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/17  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e13\u0e38\u0e28\u0e32\u0e28\u0e34\u0e23\u0e34 \u0e2a\u0e32\u0e17\u0e23-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569025234\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e30\u0e25\u0e34 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025234 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e30\u0e25\u0e34 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 300000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 63\/161  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e31\u0e21\u0e21\u0e32\u0e01\u0e23 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e0b\u0e2d\u0e22 2\/1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025421\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e08\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025421 \u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e25\u0e39\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e08\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 300000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/160  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0343569001811\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e27\u0e07\u0e21\u0e31\u0e48\u0e19 888\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001811 \u0e2b\u0e08.\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e27\u0e07\u0e21\u0e31\u0e48\u0e19 888 2569-07-07 300000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 194  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569127452\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127452 \u0e1a\u0e08.\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a \u0e25\u0e34\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 300000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19             \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 566\/95  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e18\u0e38\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c 58 \u0e41\u0e22\u0e0120 (\u0e2a\u0e32\u0e18\u0e38\u0e0a\u0e19) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022324\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e38\u0e0d\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022324 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e38\u0e0d\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 300000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 \u0e22\u0e37\u0e48\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e07\u0e32\u0e19\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23          \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 116  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0205569035425\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1a\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035425 \u0e1a\u0e08.\u0e40\u0e08\u0e1a\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 300000 69200 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 26  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0413569001535\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e28\u0e32\u0e25\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001535 \u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e1e\u0e28\u0e32\u0e25 2569-07-06 300000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0923569000194\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e34\u0e2a\u0e01\u0e35 \u0e0a\u0e47\u0e2d\u0e1b 2026\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0923569000194 \u0e2b\u0e08.\u0e23\u0e34\u0e2a\u0e01\u0e35 \u0e0a\u0e47\u0e2d\u0e1b 2026 2569-07-06 300000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01 \u0e07\u0e32\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 214\/5  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e32\u0e30\u0e40\u0e04\u0e35\u0e48\u0e22\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0115569022154\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49\u0e40\u0e1f\u0e34\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022154 \u0e1a\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49\u0e40\u0e1f\u0e34\u0e2a\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 300000 68104 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u4e0d\u52d5\u7523 9\/1  \u0e0b\u0e2d\u0e22 38 \u0e16\u0e19\u0e19\u0e17\u0e49\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569126472\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126472 \u0e1a\u0e08.\u0e40\u0e01\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e34\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 300000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e20\u0e32\u0e1e\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e16\u0e48\u0e32\u0e22\u0e27\u0e35\u0e14\u0e34\u0e42\u0e2d \u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 50\/89  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 174 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022073\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e15\u0e23\u0e32\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47999\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47999\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022073 \u0e1a\u0e08.\u0e08\u0e34\u0e15\u0e23\u0e32\u0e0d\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 300000 47999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e2d\u0e21\u0e23\u0e30\u0e40\u0e2b\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e2b\u0e2d\u0e21 \u0e01\u0e49\u0e32\u0e19\u0e2b\u0e2d\u0e21 \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e2d\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86\/94  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0433569000385\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e35\u0e15\u0e32\u0e25\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e23\u0e48\u0e14\u0e2d\u0e19\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000385 \u0e2b\u0e08.\u0e2a\u0e35\u0e15\u0e32\u0e25\u0e40\u0e01\u0e29\u0e15\u0e23\u0e44\u0e23\u0e48\u0e14\u0e2d\u0e19 2569-07-04 300000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0113569002208\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002208 \u0e2b\u0e08.\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07 2569-07-03 300000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e0b\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e41\u0e25\u0e30 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e07\u0e32\u0e19\u0e0a\u0e48\u0e32\u0e07 \u5efa\u8a2d 789\/357  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e23\u0e34\u0e40\u0e1e\u0e25\u0e2a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 90 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0143569001121\",\"name_th\":\"\u0e2b\u0e08.\u0e27.\u0e40\u0e01\u0e29\u0e15\u0e23 2\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001121 \u0e2b\u0e08.\u0e27.\u0e40\u0e01\u0e29\u0e15\u0e23 2 2569-07-03 300000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0305569006921\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e23\u0e31\u0e01 \u0e42\u0e21\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569006921 \u0e1a\u0e08.\u0e40\u0e21\u0e23\u0e31\u0e01 \u0e42\u0e21\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 300000 45403 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e2b\u0e21\u0e27\u0e01\u0e19\u0e34\u0e23\u0e20\u0e31\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 355\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e1b\u0e25\u0e34\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0505569015073\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e23\u0e34\u0e2a\u0e34\u0e23\u0e34 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015073 \u0e1a\u0e08.\u0e20\u0e39\u0e23\u0e34\u0e2a\u0e34\u0e23\u0e34 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 300000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 309  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015081\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e49\u0e19\u0e1d\u0e31\u0e19 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015081 \u0e1a\u0e08.\u0e1b\u0e31\u0e49\u0e19\u0e1d\u0e31\u0e19 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 300000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 82\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0183569000256\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e17\u0e1a\u0e32\u0e07\u0e2b\u0e21\u0e39\u0e14\u0e35 \u0e1f\u0e32\u0e23\u0e4c\u0e21\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01450\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01450\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0183569000256 \u0e2b\u0e08.\u0e42\u0e17\u0e1a\u0e32\u0e07\u0e2b\u0e21\u0e39\u0e14\u0e35 \u0e1f\u0e32\u0e23\u0e4c\u0e21 2569-07-02 300000 01450 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e38\u0e01\u0e23 \u8fb2\u6797\u6c34\u7523 103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0903569001450\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e1a\u0e35\u0e17\u0e352026 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001450 \u0e2b\u0e08.\u0e1e\u0e35\u0e1a\u0e35\u0e17\u0e352026 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-02 300000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569005244\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e2b\u0e21\u0e48\u0e2d\u0e21\u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":300000,\"capital_display\":\"300,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005244 \u0e1a\u0e08.\u0e19\u0e32\u0e2b\u0e21\u0e48\u0e2d\u0e21\u0e04\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 300000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0365569001481\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e08\u0e0d\u0e32 \u0e40\u0e2e\u0e25\u0e18\u0e4c\u0e41\u0e04\u0e23\u0e4c   \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86202\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86202\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0365569001481 \u0e1a\u0e08.\u0e42\u0e08\u0e0d\u0e32 \u0e40\u0e2e\u0e25\u0e18\u0e4c\u0e41\u0e04\u0e23\u0e4c   \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 250000 86202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e27\u0e0a\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e33\u0e1a\u0e31\u0e14 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1c\u0e14\u0e38\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e01\u0e33\u0e2b\u0e19\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2b\u0e31\u0e15\u0e16\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e20\u0e32\u0e1e\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u533b\u7642\u30fb\u798f\u7949 88\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0135569022723\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e40\u0e2e\u0e07 \u0e1b\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56292\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56292\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022723 \u0e1a\u0e08.\u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 \u0e40\u0e2e\u0e07 \u0e1b\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 250000 56292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 89\/8  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e07\u0e34\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e04\u0e39\u0e27\u0e31\u0e14-\u0e1a\u0e32\u0e07\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e074 \u0e16\u0e19\u0e19345 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0275569001172\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001172 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 250000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 46\/2  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 10 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0745569007729\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35 \u0e27\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20231\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20231\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007729 \u0e1a\u0e08.\u0e1a\u0e35 \u0e27\u0e34\u0e19 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 250000 20231 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e1a\u0e39\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1f\u0e2d\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e02\u0e31\u0e14\u0e40\u0e07\u0e32 \u0e2d\u0e32\u0e17\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e4d\u0e49\u0e32\u0e22\u0e32\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e19\u0e4d\u0e49\u0e32\u0e22\u0e32\u0e25\u0e49\u0e32\u0e07\u0e08\u0e32\u0e19 \u0e1c\u0e07\u0e0b\u0e31\u0e01\u0e1f\u0e2d\u0e01 \u0e2a\u0e1a\u0e39\u0e48\u0e40\u0e2b\u0e25\u0e27 \u0e19\u0e4d\u0e49\u0e32\u0e22\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e1c\u0e49\u0e32\u0e19\u0e38\u0e48\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e02\u0e31\u0e14\u0e40\u0e07\u0e32 \u0e04\u0e23\u0e35\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e31\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e04\u0e23\u0e35\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e41\u0e01\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30 \u0e04\u0e23\u0e35\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e31\u0e14\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 53\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569137091\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e42\u0e25\u0e27\u0e4c\u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137091 \u0e1a\u0e08.\u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e42\u0e25\u0e27\u0e4c\u0e1a\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 250000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u5bbf\u6cca\u30fb\u98f2\u98df 122\/9  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 54\/1 \u0e41\u0e22\u0e01 6-5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0193569000817\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35\u0e1a\u0e35 \u0e1f\u0e39\u0e49\u0e14\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000817 \u0e2b\u0e08.\u0e14\u0e35\u0e1a\u0e35 \u0e1f\u0e39\u0e49\u0e14\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e19\u0e39\u0e49\u0e14\u0e40\u0e14\u0e34\u0e49\u0e25 2569-07-21 250000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u5bbf\u6cca\u30fb\u98f2\u98df 16\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569136672\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e41\u0e0a\u0e1b\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136672 \u0e1a\u0e08.\u0e17\u0e23\u0e35 \u0e41\u0e0a\u0e1b\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 250000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e2a\u0e20\u0e32\u0e1e\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e01\u0e25\u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1014  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569021883\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2a\u0e07 \u0e2a\u0e42\u0e15\u0e19 69 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021883 \u0e1a\u0e08.\u0e41\u0e2a\u0e07 \u0e2a\u0e42\u0e15\u0e19 69 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 250000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e34\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 201\/1052  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569004461\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e38\u0e4a\u0e01 \u0e27\u0e2d\u0e22\u0e22\u0e32\u0e0a \u0e42\u0e04\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004461 \u0e2b\u0e08.\u0e15\u0e38\u0e4a\u0e01 \u0e27\u0e2d\u0e22\u0e22\u0e32\u0e0a \u0e42\u0e04 2569-07-07 250000 79120 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 535  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0213569001197\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e19\u0e38\u0e48\u0e19\u0e27\u0e07\u0e04\u0e4c\u0e2a\u0e38\u0e02\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001197 \u0e2b\u0e08.\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e19\u0e38\u0e48\u0e19\u0e27\u0e07\u0e04\u0e4c\u0e2a\u0e38\u0e02 2569-07-05 250000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 60  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001476\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 26\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001476 \u0e2b\u0e08.\u0e2d\u0e34\u0e19 \u0e04\u0e2d\u0e2a\u0e40\u0e21\u0e15\u0e34\u0e01 26 2569-07-04 250000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/4  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e07\u0e32\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0125569024751\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e21\u0e32\u0e2d\u0e34\u0e48\u0e21\u0e41\u0e21\u0e27\u0e2d\u0e49\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":250000,\"capital_display\":\"250,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024751 \u0e1a\u0e08.\u0e2b\u0e21\u0e32\u0e2d\u0e34\u0e48\u0e21\u0e41\u0e21\u0e27\u0e2d\u0e49\u0e27\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 250000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 138\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026036\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e14\u0e2d\u0e1f\u0e27\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 1966 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":220000,\"capital_display\":\"220,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58201\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58201\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026036 \u0e1a\u0e08.\u0e25\u0e39\u0e14\u0e2d\u0e1f\u0e27\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 1966 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 220000 58201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 42  \u0e0b\u0e2d\u0e22 \u0e40\u0e23\u0e27\u0e14\u0e35 46 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0113569002631\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e21\u0e42\u0e23\u0e14\u0e35\u0e49 \u0e40\u0e19\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2a\u0e1b\u0e32\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96104\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96104\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002631 \u0e2b\u0e08.\u0e40\u0e21\u0e42\u0e23\u0e14\u0e35\u0e49 \u0e40\u0e19\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2a\u0e1b\u0e32 2569-07-31 200000 96104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e25\u0e47\u0e1a \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e1c\u0e34\u0e27\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e17\u0e49\u0e32 \u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e1e\u0e49\u0e19\u0e17\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e25\u0e47\u0e1a\u0e1e\u0e35\u0e27\u0e35\u0e0b\u0e35 (pvc) \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e25\u0e47\u0e1a\u0e42\u0e1e\u0e25\u0e35\u0e40\u0e08\u0e25\/\u0e40\u0e08\u0e25\u0e17\u0e34\u0e1b \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e40\u0e25\u0e47\u0e1a\u0e2d\u0e30\u0e04\u0e23\u0e34\u0e25\u0e34\u0e04 \u0e17\u0e32\u0e2a\u0e35\u0e40\u0e25\u0e47\u0e1a\u0e40\u0e08\u0e25\u0e21\u0e37\u0e2d \u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 141\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569025277\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e31\u0e19\u0e19\u0e35\u0e48\u0e14\u0e31\u0e4a\u0e1a\u0e2a\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59201\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59201\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025277 \u0e1a\u0e08.\u0e2e\u0e31\u0e19\u0e19\u0e35\u0e48\u0e14\u0e31\u0e4a\u0e1a\u0e2a\u0e4c \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 200000 59201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e15\u0e49\u0e19\u0e09\u0e1a\u0e31\u0e1a (\u0e40\u0e2a\u0e35\u0e22\u0e07) \u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e25\u0e07\u0e1a\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e17\u0e1b\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e35\u0e14\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e17\u0e1b\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e38 (\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e14) \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c  \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e17\u0e35\u0e48\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e40\u0e17\u0e1b\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e31\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 199\/238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002298\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e22\u0e392022 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002298 \u0e2b\u0e08.\u0e0b\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e22\u0e392022 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 2569-07-31 200000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1e\u0e37\u0e0a \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1b\u0e35\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 221  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0803569001108\",\"name_th\":\"\u0e2b\u0e08.\u0e28.\u0e28\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001108 \u0e2b\u0e08.\u0e28.\u0e28\u0e23\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10 2569-07-31 200000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c  \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 21\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0725569002255\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e1e\u0e23\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002255 \u0e1a\u0e08.\u0e1e\u0e35 \u0e1e\u0e23\u0e13\u0e23\u0e07\u0e04\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 200000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0473569001012\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569001012 \u0e2b\u0e08.\u0e17\u0e35\u0e1e\u0e35 \u0e42\u0e01\u0e25\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-29 200000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 77  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569028233\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e08\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028233 \u0e1a\u0e08.\u0e43\u0e08\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 200000 70209 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 19\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0103569008095\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e32\u0e23\u0e34\u0e40\u0e0b\u0e35\u0e22\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008095 \u0e2b\u0e08.\u0e27\u0e32\u0e23\u0e34\u0e40\u0e0b\u0e35\u0e22 2569-07-25 200000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e17\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e41\u0e0a\u0e21\u0e1e\u0e39 \u0e2a\u0e1a\u0e39\u0e48 \u0e22\u0e32\u0e2a\u0e23\u0e30\u0e1c\u0e21 \u0e04\u0e23\u0e35\u0e21\u0e17\u0e32\u0e2b\u0e19\u0e49\u0e32 \u0e04\u0e23\u0e35\u0e21\u0e17\u0e32\u0e15\u0e31\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 266  \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141102\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e40\u0e1e\u0e47\u0e15 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141102 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e40\u0e1e\u0e47\u0e15 \u0e1e\u0e23\u0e2d\u0e2a\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 200000 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 145\/18-19  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e07\u0e29\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b217-1 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19-\u0e0a\u0e32\u0e22\u0e17\u0e30\u0e40\u0e25 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569028080\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e34\u0e44\u0e0a\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86201\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86201\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569028080 \u0e1a\u0e08.\u0e40\u0e21\u0e14\u0e34\u0e44\u0e0a\u0e25\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 200000 86201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 107\/284  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e072 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569023142\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e34\u0e21 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"38213\",\"industry_category\":\"\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"industry_label\":\"38213\uff5c\u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023142 \u0e1a\u0e08.\u0e17\u0e34\u0e21 \u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 200000 38213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1c\u0e2a\u0e21 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1a\u0e48\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u6c34\u9053\u30fb\u5ec3\u68c4\u7269\u51e6\u7406 110\/221  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000903\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000903 \u0e2b\u0e08.\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 2569-07-25 200000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 280\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0105569140971\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e19\u0e32\u0e0a\u0e34\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140971 \u0e1a\u0e08.\u0e0a\u0e19\u0e32\u0e0a\u0e34\u0e15 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 200000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19 \u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 222\/113  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e23\u0e32\u0e0d\u0e2a\u0e34\u0e23\u0e34\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0145569004903\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e1f\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43302\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43302\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004903 \u0e1a\u0e08.\u0e42\u0e19\u0e27\u0e32\u0e1f\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 200000 43302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1b\u0e39\u0e1e\u0e37\u0e49\u0e19\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5efa\u8a2d 5\/377  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e35\u0e14\u0e35\u0e41\u0e25\u0e19\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0815569002238\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e08\u0e34\u0e19\u0e14\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52229\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52229\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002238 \u0e1a\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e08\u0e34\u0e19\u0e14\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 200000 52229 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 82  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0903569001778\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e32\u0e0d\u0e0a\u0e31\u0e22 2569\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001778 \u0e2b\u0e08.\u0e0a\u0e32\u0e0d\u0e0a\u0e31\u0e22 2569 2569-07-24 200000 33200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b?\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 43\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25 63 \u0e0b\u0e2d\u0e22 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006135\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e49\u0e32\u0e27 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96202\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96202\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006135 \u0e1a\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e49\u0e32\u0e27 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 200000 96202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 425\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569138870\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2d\u0e35\u0e44\u0e2d \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138870 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e2d\u0e35\u0e44\u0e2d \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 200000 46599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 252\/115  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22-\u0e20\u0e31\u0e17\u0e23 \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 22 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139434\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35 \u0e0b\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e21\u0e42\u0e15\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139434 \u0e1a\u0e08.\u0e17\u0e35 \u0e0b\u0e35 \u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e21\u0e42\u0e15\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 200000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 301\/128  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0768(\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e07\u0e29\u0e4c2) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569038751\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e09\u0e35 \u0e19\u0e34\u0e27 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038751 \u0e1a\u0e08.\u0e44\u0e17\u0e48\u0e09\u0e35 \u0e19\u0e34\u0e27 \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 200000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 132\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0713569000561\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e1f\u0e40\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0713569000561 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e2d\u0e1f\u0e40\u0e04 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35 2569-07-23 200000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e25\u0e30\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e35 \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e23\u0e1e\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e22\u0e0a\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569137903\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e14 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137903 \u0e1a\u0e08.\u0e40\u0e1a\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e14 \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 200000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e02\u0e19\u0e21\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48\/28  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e35\u0e40\u0e27\u0e48\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027679\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e31\u0e19\u0e19\u0e34\u0e48\u0e07\u0e40\u0e1f\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027679 \u0e1a\u0e08.\u0e0b\u0e35\u0e0b\u0e31\u0e19\u0e19\u0e34\u0e48\u0e07\u0e40\u0e1f\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 200000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/168  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e1e\u0e32\u0e23\u0e4c\u0e04\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e04\u0e39\u0e25\u0e31\u0e14-\u0e27\u0e31\u0e14\u0e1a\u0e32\u0e07\u0e21\u0e48\u0e27\u0e07 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002593\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e4c\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80100\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80100\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002593 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e2d\u0e2a \u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e34\u0e15\u0e35\u0e49 \u0e01\u0e32\u0e23\u0e4c\u0e14 2569-07-22 200000 80100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 99\/234  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569009742\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e17\u0e35 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009742 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35\u0e17\u0e35 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 200000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 309  \u0e16\u0e19\u0e19\u0e40\u0e19\u0e34\u0e19\u0e1e\u0e22\u0e2d\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001692\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001692 \u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 200000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 61  \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e28\u0e23\u0e35\u0e2b\u0e21\u0e27\u0e14\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002263\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e29\u0e40\u0e17\u0e1e\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e1a\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002263 \u0e2b\u0e08.\u0e40\u0e08\u0e29\u0e40\u0e17\u0e1e\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e42\u0e1a 2569-07-22 200000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 241  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0905569005988\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e25\u0e34\u0e19\u0e18\u0e23\u0e13\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005988 \u0e1a\u0e08.\u0e13\u0e25\u0e34\u0e19\u0e18\u0e23\u0e13\u0e4c \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 200000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 134\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569137504\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e17\u0e34\u0e40\u0e19\u0e25 \u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e23\u0e39\u0e40\u0e21\u0e19\u0e40\u0e17\u0e0a\u0e31\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137504 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e17\u0e34\u0e40\u0e19\u0e25 \u0e2d\u0e34\u0e19\u0e2a\u0e15\u0e23\u0e39\u0e40\u0e21\u0e19\u0e40\u0e17\u0e0a\u0e31\u0e19 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 200000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e02\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 76  \u0e0b\u0e2d\u0e22 \u0e2a\u0e15\u0e23\u0e35\u0e27\u0e34\u0e17\u0e22\u0e32 2 \u0e0b\u0e2d\u0e22 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024076\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e35\u0e14\u0e35 \u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18119\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18119\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024076 \u0e1a\u0e08.\u0e40\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e47\u0e19 \u0e17\u0e23\u0e35\u0e14\u0e35 \u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 200000 18119 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e34 (3d printing) \u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a fdm, sla, dlp, lcd \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e27\u0e22\u0e40\u0e23\u0e0b\u0e34\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e0a\u0e34\u0e49\u0e19\u0e07\u0e32\u0e19\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a (prototype) \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 25\/111  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0313569001099\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e31\u0e19\u0e17\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 2026\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001099 \u0e2b\u0e08.\u0e19\u0e31\u0e19\u0e17\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c 2026 2569-07-21 200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 166\/28  \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e16\u0e32\u0e19\u0e35 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0503569005092\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e32\u0e20\u0e32 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005092 \u0e2b\u0e08.\u0e0a\u0e32\u0e20\u0e32 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 2569-07-21 200000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 \u5efa\u8a2d 161  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569136249\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e17 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136249 \u0e1a\u0e08.\u0e40\u0e01\u0e23\u0e17 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e17\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 200000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25\/9  \u0e0b\u0e2d\u0e22 \u0e28\u0e32\u0e25\u0e32\u0e25\u0e2d\u0e22 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 71 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023941\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e40\u0e14\u0e27\u0e34\u0e14 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023941 \u0e1a\u0e08.\u0e04\u0e34\u0e07\u0e40\u0e14\u0e27\u0e34\u0e14 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 200000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 2000\/118  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1a\u0e25\u0e47\u0e2a\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e22\u0e32\u0e07\u0e1b\u0e39 47 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17\u0e1a\u0e32\u0e07\u0e1b\u0e39 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0203569003203\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003203 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-20 200000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e2d\u0e2d\u0e1f\u0e15\u0e34\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 63\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0225569002322\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002322 \u0e1a\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 200000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e04\u0e31\u0e14\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e2a\u0e14 \u0e1c\u0e25\u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 12\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0433569000431\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08-\u0e40\u0e08\u0e47\u0e01\u0e0b\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0433569000431 \u0e2b\u0e08.\u0e40\u0e08-\u0e40\u0e08\u0e47\u0e01\u0e0b\u0e4c 2569-07-20 200000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e20\u0e32\u0e1e\u0e27\u0e32\u0e14 \u0e20\u0e32\u0e1e\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 354\/93  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0503569005068\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e07\u0e29\u0e4c\u0e1f\u0e49\u0e32\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47739\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47739\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005068 \u0e2b\u0e08.\u0e2b\u0e07\u0e29\u0e4c\u0e1f\u0e49\u0e32\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c 2569-07-20 200000 47739 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e17\u0e38\u0e01\u0e02\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 220  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016312\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e22\u0e4c\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016312 \u0e1a\u0e08.\u0e40\u0e04\u0e22\u0e4c\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 200000 47630 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e01\u0e35\u0e2c\u0e32\u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 799\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0653569001169\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48\u0e22\u0e4c \u0e40\u0e23\u0e0a\u0e0b\u0e34\u0e48\u0e07 \u0e0a\u0e47\u0e2d\u0e1b\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001169 \u0e2b\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48\u0e22\u0e4c \u0e40\u0e23\u0e0a\u0e0b\u0e34\u0e48\u0e07 \u0e0a\u0e47\u0e2d\u0e1b 2569-07-20 200000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 27\/37  \u0e0b\u0e2d\u0e22 17 \u0e16\u0e19\u0e19\u0e18\u0e23\u0e23\u0e21\u0e1a\u0e39\u0e0a\u0e32 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0833569000578\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e1b\u0e48\u0e32\u0e15\u0e2d\u0e07\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0833569000578 \u0e2b\u0e08.\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e1b\u0e48\u0e32\u0e15\u0e2d\u0e07 2569-07-20 200000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e14\u0e39\u0e14\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e0e\u0e34\u0e01\u0e39\u0e25 (\u0e14\u0e39\u0e14\u0e2a\u0e49\u0e2d\u0e21) \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 8\/7  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569135684\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135684 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e27\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 200000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 63\/12  \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e43\u0e08 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0373569000238\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e34\u0e27\u0e32 \u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e40\u0e0a\u0e1f\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"province_ja\":\"\u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\",\"search_text\":\"0373569000238 \u0e2b\u0e08.\u0e17\u0e34\u0e27\u0e32 \u0e1a\u0e2d\u0e14\u0e35\u0e49\u0e40\u0e0a\u0e1f 2569-07-18 200000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e19\u0e27\u0e14\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e19\u0e27\u0e14\u0e19\u0e4d\u0e49\u0e32\u0e21\u0e31\u0e19 \u0e19\u0e27\u0e14\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e19\u0e27\u0e14\u0e01\u0e23\u0e30\u0e0a\u0e31\u0e1a\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19 \u0e19\u0e27\u0e14\u0e2a\u0e25\u0e32\u0e22\u0e44\u0e02\u0e21\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 567  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e40\u0e08\u0e23\u0e34\u0e0d \u30a2\u30e0\u30ca\u30fc\u30c8\u30c1\u30e3\u30eb\u30fc\u30f3\u770c\"},{\"reg_no\":\"0925569001087\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e15\u0e23\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001087 \u0e1a\u0e08.\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e15\u0e23\u0e31\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 200000 75000 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 212\/19  \u0e16\u0e19\u0e19\u0e27\u0e34\u0e40\u0e28\u0e29\u0e01\u0e38\u0e25 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0105569135323\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135323 \u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 200000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c (application) \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 751 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027130\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 888 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027130 \u0e1a\u0e08.\u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 888 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 200000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e04\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e22\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e41\u0e2a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 82\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e27\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 22 \u0e41\u0e22\u0e01 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027148\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 99 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027148 \u0e1a\u0e08.\u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 99 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 200000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e04\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e22\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e41\u0e2a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 82\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e27\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 22 \u0e41\u0e22\u0e01 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027156\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 168 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027156 \u0e1a\u0e08.\u0e02\u0e38\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 168 \u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 200000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e04\u0e40\u0e25\u0e19\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e22\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e41\u0e2a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 82\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e27\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 22 \u0e41\u0e22\u0e01 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021956\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e07\u0e28\u0e32\u0e01\u0e49\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021956 \u0e1a\u0e08.\u0e2d\u0e07\u0e28\u0e32\u0e01\u0e49\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 200000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/72  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e2b\u0e17\u0e31\u0e22\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022081\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022081 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a \u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 200000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0925569001079\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e15\u0e23\u0e31\u0e07\",\"province_ja\":\"\u30c8\u30e9\u30f3\u770c\",\"search_text\":\"0925569001079 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 200000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u5efa\u8a2d 362\/75  \u0e16\u0e19\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e22\u0e2d\u0e14 \u0e08.\u0e15\u0e23\u0e31\u0e07 \u30c8\u30e9\u30f3\u770c\"},{\"reg_no\":\"0105569134254\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62090\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62090\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134254 \u0e1a\u0e08.\u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c\u0e1e\u0e2d\u0e22\u0e17\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 200000 62090 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e1c\u0e39\u0e49\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1c\u0e39\u0e49\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a \u0e27\u0e07\u0e08\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e41\u0e25\u0e30\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e23\u0e30\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e14\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u60c5\u5831\u901a\u4fe1\u30fbit 555  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e2a\u0e32 \u0e27\u0e31\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134386\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134386 \u0e1a\u0e08.\u0e01\u0e23\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 200000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e2b\u0e21\u0e27\u0e01 \u0e41\u0e27\u0e48\u0e19\u0e15\u0e32 \u0e19\u0e32\u0e2c\u0e34\u0e01\u0e32  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 742 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002488\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e32\u0e19\u0e32 \u0e42\u0e01\u0e25\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002488 \u0e2b\u0e08.\u0e1e\u0e32\u0e19\u0e32 \u0e42\u0e01\u0e25 2569-07-16 200000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1742\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 \u0e2a\u0e34\u0e19\u0e2a\u0e21\u0e1a\u0e38\u0e0d \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002526\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002526 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e25\u0e40\u0e04 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-16 200000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 8\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023525\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e23\u0e34\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023525 \u0e1a\u0e08.\u0e42\u0e19\u0e23\u0e34\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 200000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 5\/26  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e41\u0e1a\u0e23\u0e34\u0e48\u0e07 58 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 107 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0513569000759\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e23\u0e23\u0e1e \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e25\u0e34\u0e49\u0e07\u0e01\u0e4c\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000759 \u0e2b\u0e08.\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e23\u0e23\u0e1e \u0e40\u0e25\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e25\u0e34\u0e49\u0e07\u0e01\u0e4c 2569-07-16 200000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e43\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2d\u0e31\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e17\u0e39\u0e15 \u0e2a\u0e16\u0e32\u0e19\u0e01\u0e07\u0e2a\u0e38\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49 22.1. \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e25\u0e30\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23, \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19, \u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 22.2. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27, \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19, \u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38 \u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 22.3. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e01\u0e49\u0e44\u0e02\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e25\u0e07\u0e15\u0e23\u0e32 (visa) \u0e43\u0e2b\u0e49\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e04\u0e19\u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 22.4. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07, \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e41\u0e17\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07, \u0e01\u0e32\u0e23\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 (certificate of identity : ci) 22.5. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07, \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23,\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e01\u0e49\u0e44\u0e02 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 22.6. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e41\u0e08\u0e49\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27, \u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07,\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07, \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19, \u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e15\u0e19 22.7. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2d\u0e33\u0e19\u0e32\u0e08 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e  \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07 \u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 22.8. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e20\u0e32\u0e29\u0e35\u0e40\u0e07\u0e34\u0e19\u0e44\u0e14\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32, \u0e01\u0e32\u0e23\u0e2b\u0e31\u0e01\u0e20\u0e32\u0e29\u0e35 \u0e13 \u0e17\u0e35\u0e48\u0e08\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e20\u0e32\u0e29\u0e35\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07 (\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22) 22.9. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\/\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23,\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e07\u0e32\u0e19\/\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\/\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 22.10. \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23,\u0e07\u0e32\u0e19\u0e41\u0e1b\u0e25\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23, \u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23, \u0e07\u0e32\u0e19\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e41\u0e1a\u0e1a\u0e1f\u0e2d\u0e23\u0e4c\u0e21, \u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1c\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e21\u0e2d\u0e1a\u0e2d\u0e33\u0e19\u0e32\u0e08 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0735569007249\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007249 \u0e1a\u0e08.\u0e40\u0e04 \u0e1e\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 200000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 25\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0775569003014\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19\u0e1a\u0e23\u0e34\u0e27 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569003014 \u0e1a\u0e08.\u0e40\u0e0b\u0e32\u0e17\u0e4c\u0e40\u0e17\u0e34\u0e23\u0e4c\u0e19\u0e1a\u0e23\u0e34\u0e27 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 200000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 38\/14  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e02\u0e32\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0835569013175\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e01\u0e34\u0e15 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013175 \u0e1a\u0e08.\u0e20\u0e39\u0e01\u0e34\u0e15 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 200000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 38\/137  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e29\u0e0e\u0e32\u0e23\u0e33\u0e25\u0e36\u0e01 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e30\u0e29\u0e31\u0e15\u0e23\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0135569021760\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e27\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45202\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45202\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021760 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e27\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 200000 45202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e15\u0e31\u0e27\u0e16\u0e31\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e01\u0e38\u0e0d\u0e41\u0e08 \u0e01\u0e31\u0e19\u0e0a\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e48\u0e19\u0e2a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 30\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0303569002745\",\"name_th\":\"\u0e2b\u0e08.\u0e2e\u0e2d\u0e27\u0e4c\u0e04 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55909\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55909\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002745 \u0e2b\u0e08.\u0e2e\u0e2d\u0e27\u0e4c\u0e04 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 2569-07-15 200000 55909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e48\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 800  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0403569003163\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003163 \u0e2b\u0e08.\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 2569-07-15 200000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e47\u0e2d\u0e1b \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 789  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013159\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e34\u0e19\u0e15\u0e34\u0e19 (\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2b\u0e34\u0e19) 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82920\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82920\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013159 \u0e1a\u0e08.\u0e15\u0e34\u0e19\u0e15\u0e34\u0e19 (\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e2b\u0e34\u0e19) 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 200000 82920 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 25\/10  \u0e0b\u0e2d\u0e22 \u0e15\u0e25\u0e34\u0e48\u0e07\u0e0a\u0e31\u0e19 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569007536\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e01\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e34\u0e25\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007536 \u0e2b\u0e08.\u0e42\u0e01\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e34\u0e25 2569-07-14 200000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 43\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0123569002151\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e07\u0e04\u0e25 \u0e2d\u0e34\u0e19\u0e0b\u0e39\u0e40\u0e25\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43291\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43291\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002151 \u0e2b\u0e08.\u0e21\u0e07\u0e04\u0e25 \u0e2d\u0e34\u0e19\u0e0b\u0e39\u0e40\u0e25\u0e0a\u0e31\u0e48\u0e19 2569-07-14 200000 43291 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19\u0e2b\u0e38\u0e49\u0e21\u0e09\u0e19\u0e27\u0e19\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e09\u0e19\u0e27\u0e19\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 7\/46  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009343\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e4a\u0e2d\u0e1a\u0e1a\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009343 \u0e1a\u0e08.\u0e14\u0e4a\u0e2d\u0e1a\u0e1a\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 200000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e39\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 89\/4  \u0e0b\u0e2d\u0e22 \u0e41\u0e2b\u0e25\u0e21\u0e01\u0e23\u0e30\u0e17\u0e37\u0e2d \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003787\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e32\u0e19 \u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003787 \u0e1a\u0e08.\u0e0a\u0e32\u0e19 \u0e23\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 191\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0575569004535\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e27\u0e07\u0e28\u0e4c \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10291\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10291\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004535 \u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e27\u0e07\u0e28\u0e4c \u0e1f\u0e39\u0e49\u0e14\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 200000 10291 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e44\u0e01\u0e48 \u0e1b\u0e25\u0e32\u0e2a\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 184  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0803569000993\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35. \u0e20\u0e39\u0e40\u0e1a\u0e28\u0e23\u0e4c\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46632\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46632\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000993 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35. \u0e20\u0e39\u0e40\u0e1a\u0e28\u0e23\u0e4c 2569-07-14 200000 46632 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e21\u0e49\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e44\u0e21\u0e49\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e44\u0e21\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 250  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569132201\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e14\u0e35\u0e44\u0e2d\u0e27\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132201 \u0e1a\u0e08.\u0e21\u0e31\u0e19\u0e19\u0e35\u0e48 \u0e14\u0e35\u0e44\u0e2d\u0e27\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 200000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e34\u0e40\u0e27\u0e19\u0e15\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 554\/105  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132570\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e34\u0e15\u0e41\u0e1a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132570 \u0e1a\u0e08.\u0e2e\u0e34\u0e15\u0e41\u0e1a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 200000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e02\u0e2d\u0e07\u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u82b8\u8853\u30fb\u5a2f\u697d 21\/75  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 34 \u0e41\u0e22\u0e01 19 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569037100\",\"name_th\":\"\u0e1a\u0e08.\u0e43\u0e08\u0e23\u0e31\u0e01 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18\u0e21\u0e39\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43120\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43120\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037100 \u0e1a\u0e08.\u0e43\u0e08\u0e23\u0e31\u0e01 \u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18\u0e21\u0e39\u0e1f\u0e27\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 200000 43120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e16\u0e21\u0e14\u0e34\u0e19 \u0e16\u0e21\u0e17\u0e23\u0e32\u0e22 \u0e02\u0e38\u0e14\u0e14\u0e34\u0e19 \u0e15\u0e31\u0e01\u0e14\u0e34\u0e19 \u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30 \u0e1a\u0e14\u0e2d\u0e31\u0e14 \u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e1b\u0e23\u0e31\u0e1a\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 89\/51  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e20\u0e31\u0e2a\u0e2a\u0e23 \u0e01\u0e23\u0e35\u0e19 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0503569004801\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e19\u0e34\u0e14\u0e32\u0e40\u0e1f\u0e2d\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e21\u0e49\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004801 \u0e2b\u0e08.\u0e27\u0e19\u0e34\u0e14\u0e32\u0e40\u0e1f\u0e2d\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e44\u0e21\u0e49 2569-07-13 200000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 190  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004827\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e38\u0e0a\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46315\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46315\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004827 \u0e2b\u0e08.\u0e19\u0e38\u0e0a\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-13 200000 46315 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e49\u0e32\u0e27\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015821\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e23\u0e0b\u0e35\u0e48 \u0e2e\u0e34\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015821 \u0e1a\u0e08.\u0e42\u0e23\u0e0b\u0e35\u0e48 \u0e2e\u0e34\u0e25\u0e25\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 200000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 2\/2  \u0e0b\u0e2d\u0e22 2 \u0e16\u0e19\u0e19\u0e21\u0e13\u0e35\u0e19\u0e1e\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000708\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e40\u0e08 \u0e17\u0e23\u0e31\u0e04\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000708 \u0e2b\u0e08.\u0e44\u0e2d\u0e1e\u0e35\u0e40\u0e08 \u0e17\u0e23\u0e31\u0e04 2569-07-13 200000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u904b\u8f38\u30fb\u7269\u6d41 139\/68  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0525569001650\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0525569001650 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e19\u0e35\u0e22\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 200000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u6559\u80b2 172  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569002191\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e49\u0e21\u0e15\u0e33\u0e17\u0e48\u0e32\u0e02\u0e31\u0e19\u0e17\u0e2d\u0e07\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002191 \u0e2b\u0e08.\u0e2a\u0e49\u0e21\u0e15\u0e33\u0e17\u0e48\u0e32\u0e02\u0e31\u0e19\u0e17\u0e2d\u0e07 2569-07-13 200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2a\u0e49\u0e21\u0e15\u0e33 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e17\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e49\u0e32\u0e19 \u0e19\u0e33\u0e01\u0e25\u0e31\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 246  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0905569005708\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e2d\u0e23\u0e34\u0e0b\u0e2d\u0e19 \u0e40\u0e2d\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005708 \u0e1a\u0e08.\u0e2e\u0e2d\u0e23\u0e34\u0e0b\u0e2d\u0e19 \u0e40\u0e2d\u0e1f\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48\u0e15\u0e4c \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e04\u0e47\u0e2d\u0e01\u0e40\u0e17\u0e04\u0e40\u0e25\u0e32\u0e08\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 255\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0745569007290\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47733\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47733\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007290 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 200000 47733 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 28\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e14\u0e32\u0e1a \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0903569001590\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e21\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001590 \u0e2b\u0e08.\u0e40\u0e25\u0e34\u0e1f \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e1f\u0e39\u0e21 2569-07-12 200000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/7  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e07\u0e32\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569007331\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007331 \u0e2b\u0e08.\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e04\u0e39\u0e48\u0e04\u0e34\u0e14\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 2569-07-10 200000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 65\/87  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e42\u0e0b\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 87 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 16 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e2d\u0e2a\u0e1b\u0e32\u0e22\u0e2a\u0e32\u0e17\u0e23-\u0e15\u0e32\u0e01\u0e2a\u0e34\u0e19(\u0e04\u0e2d\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e42\u0e0b\u0e19) \u0e0b\u0e2d\u0e22 \u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0143569001171\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2d\u0e34\u0e48\u0e21\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0143569001171 \u0e2b\u0e08.\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2d\u0e34\u0e48\u0e21 2569-07-10 200000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e1e\u0e23\u0e35\u0e2d\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e2b\u0e34\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 55\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0503569004584\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e38\u0e49\u0e21 2 \u0e2b\u0e21\u0e39\u0e08\u0e38\u0e48\u0e21 \u0e2b\u0e27\u0e32\u0e19\u0e40\u0e08\u0e35\u0e4a\u0e22\u0e1a\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004584 \u0e2b\u0e08.\u0e0b\u0e38\u0e49\u0e21 2 \u0e2b\u0e21\u0e39\u0e08\u0e38\u0e48\u0e21 \u0e2b\u0e27\u0e32\u0e19\u0e40\u0e08\u0e35\u0e4a\u0e22\u0e1a 2569-07-10 200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 236\/10  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e0b\u0e19 c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 c1-c3 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e27\u0e25\u0e32\u0e22 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0633569000685\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e25\u0e31\u0e2a 168\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e15\u0e32\u0e01\",\"province_ja\":\"\u30bf\u30fc\u30af\u770c\",\"search_text\":\"0633569000685 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1e\u0e25\u0e31\u0e2a 168 2569-07-10 200000 11041 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u88fd\u9020 82\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e15\u0e32\u0e01 \u30bf\u30fc\u30af\u770c\"},{\"reg_no\":\"0705569003120\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e1e\u0e34\u0e27\u0e40\u0e25\u0e34\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e27\u0e17\u0e31\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003120 \u0e1a\u0e08.\u0e2d\u0e2d\u0e1e\u0e34\u0e27\u0e40\u0e25\u0e34\u0e19\u0e0b\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e27\u0e17\u0e31\u0e25\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 200000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e08\u0e32\u0e01\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 7\/3  \u0e16\u0e19\u0e19\u0e41\u0e2a\u0e07\u0e0a\u0e39\u0e42\u0e15 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0745569007265\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e49\u0e32 \u0e40\u0e17\u0e04 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007265 \u0e1a\u0e08.\u0e40\u0e2e\u0e49\u0e32 \u0e40\u0e17\u0e04 \u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 200000 46421 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e2d\u0e17\u0e35  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/96  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e27\u0e34\u0e40\u0e28\u0e29\u0e2a\u0e38\u0e02 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e31\u0e22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569130411\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e21\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e39\u0e49\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130411 \u0e1a\u0e08. \u0e40\u0e21\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e21\u0e39\u0e49\u0e14  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e1c\u0e2a\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 61  \u0e16\u0e19\u0e19\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e22 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002313\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e2d \u0e1e\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002313 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e2d \u0e1e\u0e35 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-09 200000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 99\/73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025668\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e40\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e17\u0e2a\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025668 \u0e1a\u0e08.\u0e1a\u0e34\u0e25\u0e40\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e17\u0e2a\u0e15\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e17\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 200000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 24  \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c 18 \u0e41\u0e22\u0e01 7\/1 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025919\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e40\u0e0b\u0e25\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025919 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e40\u0e0b\u0e25\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e2d\u0e44\u0e2d \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 200000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (ai) \u60c5\u5831\u901a\u4fe1\u30fbit 99\/146  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e34\u0e27\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2d\u0e40\u0e27\u0e19\u0e34\u0e27 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 11 \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025960\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025960 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e21\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 200000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e23\u0e49\u0e2d\u0e22\u0e04\u0e2d \u0e2a\u0e23\u0e49\u0e2d\u0e22\u0e02\u0e49\u0e2d\u0e21\u0e37\u0e2d \u0e15\u0e48\u0e32\u0e07\u0e2b\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e2b\u0e27\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e44\u0e02\u0e48\u0e21\u0e38\u0e01 \u0e2b\u0e34\u0e19\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e41\u0e17\u0e49\u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 219\/35  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e18\u0e19\u0e32\u0e04\u0e25\u0e31\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e39 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036413\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036413 \u0e1a\u0e08.\u0e04\u0e32\u0e23\u0e4c\u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 200000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19  \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 241\/104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0743569000943\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35 \u0e2a\u0e01\u0e23\u0e35\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14120\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14120\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000943 \u0e2b\u0e08.\u0e17\u0e35 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e35 \u0e2a\u0e01\u0e23\u0e35\u0e19 2569-07-09 200000 14120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22  \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u88fd\u9020 1\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569128734\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e40\u0e18\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0105569128734 \u0e1a\u0e08.\u0e40\u0e21\u0e40\u0e18\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 200000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 155\/3  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e20\u0e39\u0e21\u0e34 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569129072\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e14\u0e31\u0e2a\u0e15\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45303\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45303\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129072 \u0e1a\u0e08.\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e14\u0e31\u0e2a\u0e15\u0e4c \u0e04\u0e32\u0e23\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 200000 45303 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e15\u0e34\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e35\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1b\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e2a\u0e35\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e01\u0e32\u0e27 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e22\u0e36\u0e14\u0e15\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 228\/4  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e44\u0e2d\u0e40\u0e23\u0e2a \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 19 \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 26 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129340\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e19\u0e27\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129340 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e42\u0e19\u0e27\u0e32  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 200000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (artificial intelligence: ai) \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e15\u0e34\u0e49\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e35.\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 350310 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569002916\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002916 \u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c 2569-07-08 200000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e41\u0e1a\u0e48\u0e07\u0e41\u0e22\u0e01 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u4e0d\u52d5\u7523 66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0585569000271\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19\",\"province_ja\":\"\u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\",\"search_text\":\"0585569000271 \u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 200000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 169  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e41\u0e21\u0e48\u0e2e\u0e48\u0e2d\u0e07\u0e2a\u0e2d\u0e19 \u30e1\u30fc\u30db\u30f3\u30bd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569127827\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e28\u0e30\u0e20\u0e31\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127827 \u0e1a\u0e08.\u0e17\u0e35\u0e28\u0e30\u0e20\u0e31\u0e17\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 200000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c(ai) \u60c5\u5831\u901a\u4fe1\u30fbit 6\/32  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 30 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569020941\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e40\u0e27\u0e2a\u0e1b\u0e49\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45405\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45405\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020941 \u0e1a\u0e08.\u0e40\u0e2d\u0e17\u0e35 \u0e01\u0e32\u0e23\u0e32\u0e08 \u0e40\u0e27\u0e2a\u0e1b\u0e49\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 200000 45405 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/253,254  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0203569002835\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e21\u0e27\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002835 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e21\u0e27\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 2569-07-07 200000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 49\/21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035921\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e07\u0e49\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035921 \u0e1a\u0e08.\u0e42\u0e07\u0e49\u0e27\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 200000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 207\/3  \u0e0b\u0e2d\u0e22 \u0e11\u0e35\u0e06\u0e32\u0e21\u0e32\u0e23\u0e04 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0453569000997\",\"name_th\":\"\u0e2b\u0e08.101 \u0e19\u0e4a\u0e2d\u0e15\u0e40\u0e25\u0e2a\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569000997 \u0e2b\u0e08.101 \u0e19\u0e4a\u0e2d\u0e15\u0e40\u0e25\u0e2a 2569-07-07 200000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e4a\u0e2d\u0e15\u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 388  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0653569001061\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e27\u0e35\u0e40\u0e04 89\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001061 \u0e2b\u0e08.\u0e17\u0e35\u0e27\u0e35\u0e40\u0e04 89 2569-07-07 200000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 72\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0103569006963\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006963 \u0e2b\u0e08.\u0e27\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c99 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-06 200000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 300\/143  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0735569006781\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e21\u0e34\u0e04\u0e38\u0e08\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006781 \u0e1a\u0e08.\u0e04\u0e38\u0e21\u0e34\u0e04\u0e38\u0e08\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 200000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 67\/211  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0903569001484\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e47\u0e2d\u0e1b\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001484 \u0e2b\u0e08.\u0e0a\u0e47\u0e2d\u0e1b\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19 2569-07-04 200000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/4  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e07\u0e32\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569006874\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e08 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006874 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e1e\u0e35\u0e40\u0e08 \u0e40\u0e1a\u0e1f\u0e40\u0e27\u0e2d\u0e40\u0e23\u0e08 2569-07-03 200000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e42\u0e22\u0e40\u0e01\u0e34\u0e23\u0e4c\u0e15 \u0e19\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/85  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e278 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126324\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e25\u0e2d\u0e08\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126324 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e25\u0e2d\u0e08\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 200000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e38\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 554  \u0e0b\u0e2d\u0e22 \u0e21.\u0e1e\u0e38\u0e14\u0e15\u0e32\u0e19 \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0395569000426\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e23\u0e34\u0e07\u0e43\u0e08 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000426 \u0e1a\u0e08.\u0e08\u0e23\u0e34\u0e07\u0e43\u0e08 \u0e42\u0e1f\u0e23\u0e40\u0e0b\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 200000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 335  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e23\u0e35\u0e2a\u0e07\u0e48\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0105569125514\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35.\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125514 \u0e1a\u0e08.\u0e1e\u0e35.\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 200000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/4 \u0e15\u0e23\u0e2d\u0e01\u0e27\u0e31\u0e14\u0e42\u0e2a\u0e21\u0e19\u0e31\u0e2a \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e40\u0e19\u0e35\u0e22\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569020518\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e14\u0e35\u0e49 \u0e40\u0e2d\u0e21\u0e21\u0e48\u0e32 \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020518 \u0e1a\u0e08.\u0e40\u0e25\u0e14\u0e35\u0e49 \u0e40\u0e2d\u0e21\u0e21\u0e48\u0e32 \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 200000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 89\/92  \u0e2d\u0e32\u0e04\u0e32\u0e23a, nue core khukot station \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 18 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0203569002771\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e23\u0e32\u0e01\u0e23\u0e28\u0e34\u0e23\u0e34\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002771 \u0e2b\u0e08.\u0e19\u0e23\u0e32\u0e01\u0e23\u0e28\u0e34\u0e23\u0e34 2569-07-02 200000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 794\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034950\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e35\u0e22\u0e07 \u0e40\u0e0b\u0e19\u0e08\u0e39\u0e23\u0e35\u0e48 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034950 \u0e1a\u0e08.\u0e15\u0e49\u0e32\u0e40\u0e2b\u0e25\u0e35\u0e22\u0e07 \u0e40\u0e0b\u0e19\u0e08\u0e39\u0e23\u0e35\u0e48 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 200000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32  \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e42\u0e25\u0e2b\u0e30 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 318\/142  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0315569001813\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e0b\u0e35 \u0e42\u0e21\u0e42\u0e15 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0315569001813 \u0e1a\u0e08.\u0e40\u0e08\u0e0b\u0e35 \u0e42\u0e21\u0e42\u0e15 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 200000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 205  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0355569000370\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"30912\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"30912\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23\",\"province_ja\":\"\u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0355569000370 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e0b\u0e35 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e48\u0e07\u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 200000 30912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u88fd\u9020 462  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e22\u0e42\u0e2a\u0e18\u0e23 \u30e4\u30bd\u30fc\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569001992\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e23\u0e38\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 99 \u0e02\u0e19\u0e2a\u0e48\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569001992 \u0e2b\u0e08.\u0e40\u0e1e\u0e35\u0e22\u0e23\u0e23\u0e38\u0e48\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c 99 \u0e02\u0e19\u0e2a\u0e48\u0e07 2569-07-02 200000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 500\/119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569123881\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e27\u0e31\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123881 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e27\u0e31\u0e19\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e32\u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 200000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b\u0e40\u0e40\u0e25\u0e30\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01  \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 2823\/3  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e32\u0e22\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2008 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021701\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e42\u0e04\u0e25\u0e34\u0e1f (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021701 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e42\u0e04\u0e25\u0e34\u0e1f (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 200000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e01\u0e35\u0e2c\u0e32 \u0e0a\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e23\u0e29\u0e41\u0e25\u0e30\u0e2a\u0e15\u0e23\u0e35 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 b-072 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024602\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e2d\u0e14\u0e40\u0e04\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52213\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52213\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024602 \u0e1a\u0e08.\u0e08\u0e2d\u0e14\u0e40\u0e04\u0e35\u0e22\u0e07\u0e02\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 200000 52213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e23\u0e16 \u0e41\u0e25\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u904b\u8f38\u30fb\u7269\u6d41 63\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 3 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002194\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e41\u0e17\u0e23\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002194 \u0e2b\u0e08.\u0e1f\u0e32\u0e2a\u0e15\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e41\u0e17\u0e23\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-01 200000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 79\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020275\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e1e\u0e48\u0e2d\u0e17\u0e2d\u0e07\u0e40\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21002\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21002\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020275 \u0e1a\u0e08.\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e1e\u0e48\u0e2d\u0e17\u0e2d\u0e07\u0e40\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 200000 21002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e22\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 234\/492  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e34\u0e15\u0e35\u0e49\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-345 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0513569000643\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e21\u0e32\u0e19 \u0e25\u0e33\u0e1e\u0e39\u0e19\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000643 \u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e21\u0e32\u0e19 \u0e25\u0e33\u0e1e\u0e39\u0e19 2569-07-01 200000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e34\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e40\u0e40\u0e2a\u0e07 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 124  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0563569000597\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e21\u0e32\u0e19 \u0e1e\u0e30\u0e40\u0e22\u0e32\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":200000,\"capital_display\":\"200,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0563569000597 \u0e2b\u0e08.\u0e04\u0e39\u0e25\u0e21\u0e32\u0e19 \u0e1e\u0e30\u0e40\u0e22\u0e32 2569-07-01 200000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e34\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e23\u0e2d\u0e07\u0e40\u0e40\u0e2a\u0e07 \u0e1f\u0e34\u0e25\u0e4c\u0e21\u0e01\u0e31\u0e19\u0e23\u0e2d\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 649\/17  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0835569012535\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e2a\u0e4c 002 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":175000,\"capital_display\":\"175,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012535 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e0a\u0e31\u0e27\u0e23\u0e35\u0e48 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32\u0e2a\u0e4c 002 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 175000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14  \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 159\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0105569129421\",\"name_th\":\"\u0e1a\u0e08.\u0e1c\u0e25\u0e34\u0e19\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":168000,\"capital_display\":\"168,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129421 \u0e1a\u0e08.\u0e1c\u0e25\u0e34\u0e19\u0e20\u0e31\u0e17\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 168000 73101 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 5\/58  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e2d\u0e15\u0e42\u0e15\u0e49 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0265569000834\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e22\u0e39\u0e48\u0e27 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46530\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46530\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\",\"search_text\":\"0265569000834 \u0e1a\u0e08.\u0e0b\u0e35\u0e22\u0e39\u0e48\u0e27 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 150000 46530 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 215  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u30ca\u30b3\u30fc\u30f3\u30ca\u30fc\u30e8\u30c3\u30af\u770c\"},{\"reg_no\":\"0105569139892\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e01\u0e25\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11049\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11049\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139892 \u0e1a\u0e08.\u0e19\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e01\u0e25\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 150000 11049 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2d\u0e2d\u0e25\u0e4c \u88fd\u9020 149\/28  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0835569013540\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e32\u0e17\u0e4c \u0e40\u0e2d\u0e32\u0e17\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013540 \u0e1a\u0e08.\u0e40\u0e2d\u0e32\u0e17\u0e4c \u0e40\u0e2d\u0e32\u0e17\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 150000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e07\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 158\/11  \u0e16\u0e19\u0e19\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0123569002232\",\"name_th\":\"\u0e2b\u0e08.\u0e59 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e35\u0e14\u0e35\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002232 \u0e2b\u0e08.\u0e59 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e21\u0e35\u0e14\u0e35 2569-07-17 150000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 70\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0905569005856\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005856 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 150000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u4e0d\u52d5\u7523 68\/53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e2a\u0e01\u0e38\u0e25\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0713569000536\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e08\u0e35 \u0e40\u0e1e\u0e32\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0713569000536 \u0e2b\u0e08.\u0e40\u0e04\u0e17\u0e35\u0e08\u0e35 \u0e40\u0e1e\u0e32\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-16 150000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 5\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0303569002729\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002729 \u0e2b\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e42\u0e23\u0e08\u0e19\u0e4c \u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-14 150000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 37\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0613569000189\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e31\u0e1e\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e27\u0e23\u0e4c\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0613569000189 \u0e2b\u0e08.\u0e2d\u0e31\u0e1e\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e27\u0e23\u0e4c 2569-07-14 150000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 46\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0573569002174\",\"name_th\":\"\u0e2b\u0e08.\u0e2b\u0e2d\u0e21\u0e1f\u0e38\u0e49\u0e07 \u0e40\u0e2e\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e25 \u0e17\u0e35\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46319\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46319\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002174 \u0e2b\u0e08.\u0e2b\u0e2d\u0e21\u0e1f\u0e38\u0e49\u0e07 \u0e40\u0e2e\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e25 \u0e17\u0e35 2569-07-13 150000 46319 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e0a\u0e32\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21\u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 283  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0903569001581\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e32\u0e19\u0e33\u0e42\u0e0a\u0e04\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46322\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46322\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001581 \u0e2b\u0e08.\u0e0a\u0e32\u0e19\u0e33\u0e42\u0e0a\u0e04 2569-07-12 150000 46322 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/104\/1  \u0e16\u0e19\u0e19\u0e2a\u0e23\u0e30\u0e40\u0e01\u0e29 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569130887\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e23\u0e14\u0e01 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130887 \u0e1a\u0e08.\u0e21\u0e23\u0e14\u0e01 \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 150000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35 \u0e41\u0e25\u0e30\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 7\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e3410 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e255 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0413569001594\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e19\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e23\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001594 \u0e2b\u0e08.\u0e18\u0e19\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e39\u0e15\u0e23 2569-07-10 150000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 461\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0743569000978\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e35. \u0e2a\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569000978 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a.\u0e14\u0e35. \u0e2a\u0e34\u0e23\u0e34\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c 2569-07-10 150000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 48\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0183569000264\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c65\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0183569000264 \u0e2b\u0e08.\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c65 2569-07-09 150000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 71\/20  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0203569002959\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e20\u0e32\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e2a\u0e2b\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002959 \u0e2b\u0e08.\u0e27\u0e34\u0e20\u0e32\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e4c\u0e2a\u0e2b\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-09 150000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 5\/271  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025323\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e4a\u0e14 \u0e40\u0e23\u0e04\u0e04\u0e2d\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90001\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90001\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025323 \u0e1a\u0e08.\u0e14\u0e39\u0e4a\u0e14 \u0e40\u0e23\u0e04\u0e04\u0e2d\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 150000 90001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e15\u0e48\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e23\u0e49\u0e2d\u0e07 \u0e17\u0e33\u0e19\u0e2d\u0e07 \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e07\u0e32\u0e19 \u0e40\u0e1e\u0e25\u0e07 (produce) \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u82b8\u8853\u30fb\u5a2f\u697d 89\/375  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569127215\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e22\u0e2d\u0e23\u0e21\u0e31\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127215 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e40\u0e22\u0e2d\u0e23\u0e21\u0e31\u0e19 \u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 150000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 28\/159  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022294\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04.\u0e14\u0e35.\u0e40\u0e2d \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022294 \u0e1a\u0e08.\u0e40\u0e04.\u0e14\u0e35.\u0e40\u0e2d \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2026 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 150000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 89\/74  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e2890 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0463569000687\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e072526\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0463569000687 \u0e2b\u0e08.\u0e2a\u0e38\u0e19\u0e17\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e072526 2569-07-03 150000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 103  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0733569000960\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e20\u0e34\u0e0d\u0e0d\u0e32\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569000960 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e1e\u0e35 \u0e20\u0e34\u0e0d\u0e0d\u0e32 2569-07-03 150000 82110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 180  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0205569035034\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035034 \u0e1a\u0e08.\u0e27\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e49\u0e07\u0e04\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 150000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e14\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e41\u0e1f\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e2a\u0e32\u0e23\u0e01\u0e32\u0e41\u0e1f \u0e01\u0e32\u0e41\u0e1f\u0e04\u0e31\u0e48\u0e27 \u0e01\u0e32\u0e41\u0e1f\u0e1a\u0e14 \u0e02\u0e19\u0e21\u0e2d\u0e1a\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 136\/51  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e07\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e31\u0e17\u0e22\u0e32 6 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0413569001471\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08 \u0e40\u0e17\u0e04 \u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":150000,\"capital_display\":\"150,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001471 \u0e2b\u0e08.\u0e40\u0e08 \u0e40\u0e17\u0e04 \u0e42\u0e1b\u0e23\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-02 150000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e22\u0e25\u0e48\u0e2d\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23 \u5efa\u8a2d 310\/255  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569140718\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e21\u0e34\u0e15 3304 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":140000,\"capital_display\":\"140,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140718 \u0e1a\u0e08.\u0e19\u0e34\u0e21\u0e34\u0e15 3304 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 140000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 109\/287  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140831\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e34\u0e21\u0e34\u0e15 3305 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":140000,\"capital_display\":\"140,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140831 \u0e1a\u0e08.\u0e19\u0e34\u0e21\u0e34\u0e15 3305 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 140000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 109\/287  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e02\u0e38\u0e19\u0e40\u0e17\u0e35\u0e22\u0e19 14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135641\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e23\u0e42\u0e0a \u0e14\u0e34\u0e0b\u0e17\u0e34\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":120000,\"capital_display\":\"120,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46321\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46321\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135641 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e23\u0e42\u0e0a \u0e14\u0e34\u0e0b\u0e17\u0e34\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 120000 46321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e44\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e02\u0e2d\u0e07\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e20\u0e32\u0e0a\u0e19\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 157-159-161  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e24\u0e17\u0e18\u0e34\u0e4c \u0e16\u0e19\u0e19\u0e40\u0e22\u0e32\u0e27\u0e23\u0e32\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0443569000822\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32-\u0e1b\u0e25\u0e32\u0e27\u0e32\u0e2c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":120000,\"capital_display\":\"120,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000822 \u0e2b\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32-\u0e1b\u0e25\u0e32\u0e27\u0e32\u0e2c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-13 120000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 174  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0403569002949\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e40\u0e01\u0e23\u0e19\u0e2a\u0e4c\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":120000,\"capital_display\":\"120,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002949 \u0e2b\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c\u0e40\u0e01\u0e23\u0e19\u0e2a\u0e4c 2569-07-04 120000 46201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e19\u0e32 \u0e17\u0e33\u0e2a\u0e27\u0e19 \u0e17\u0e33\u0e44\u0e23\u0e48 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0465569000808\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e42\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":120000,\"capital_display\":\"120,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000808 \u0e1a\u0e08.\u0e40\u0e04\u0e25\u0e35\u0e22\u0e23\u0e4c\u0e42\u0e19\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 120000 81210 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 50  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e22\u0e32\u0e07\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0363569000840\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e23\u0e0b\u0e4c\u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":110000,\"capital_display\":\"110,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10611\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10611\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000840 \u0e2b\u0e08.\u0e44\u0e23\u0e0b\u0e4c\u0e1e\u0e25\u0e31\u0e2a \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 2569-07-08 110000 10611 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e42\u0e23\u0e07\u0e2a\u0e35 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e42\u0e23\u0e07\u0e19\u0e49\u0e33\u0e41\u0e02\u0e47\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e38\u0e23\u0e32 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u88fd\u9020 73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0715569002778\",\"name_th\":\"\u0e1a\u0e08.1988 \u0e40\u0e04 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":105000,\"capital_display\":\"105,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002778 \u0e1a\u0e08.1988 \u0e40\u0e04 \u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e2a \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 105000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0903569001701\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e27\u0e32\u0e23\u0e4c\u0e1b\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":105000,\"capital_display\":\"105,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001701 \u0e2b\u0e08.\u0e40\u0e28\u0e23\u0e29\u0e10\u0e35\u0e27\u0e32\u0e23\u0e4c\u0e1b 2569-07-20 105000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/13  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e2a\u0e1b\u0e23\u0e34\u0e07\u0e44\u0e25\u0e1f\u0e4c \u0e04\u0e25\u0e2d\u0e07\u0e41\u0e2b \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07\u0e41\u0e2b-\u0e04\u0e39\u0e40\u0e15\u0e48\u0e32 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569142915\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e44\u0e23\u0e0b\u0e4c \u0e41\u0e2d\u0e42\u0e23\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142915 \u0e1a\u0e08.\u0e2d\u0e44\u0e23\u0e0b\u0e4c \u0e41\u0e2d\u0e42\u0e23\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 64202 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e32\u0e02\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e22\u0e48\u0e2d\u0e22 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e23\u0e48\u0e27\u0e21\u0e17\u0e38\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e41\u0e2b\u0e48\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e08\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e02\u0e49\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e1a\u0e31\u0e15\u0e23 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e15\u0e23\u0e32\u0e2a\u0e32\u0e23\u0e43\u0e14\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e43\u0e14\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e14\u0e46 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e27\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1a\u0e48\u0e07\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e17\u0e38\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e04\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e43\u0e14\u0e46 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e08\u0e30\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e23\u0e07\u0e01\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e25\u0e49\u0e32\u0e22\u0e04\u0e25\u0e36\u0e07\u0e01\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30 \u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u91d1\u878d\u30fb\u4fdd\u967a 111 \u0e17\u0e23\u0e39 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e40\u0e27\u0e2a\u0e15\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e22\u0e39\u0e19\u0e34\u0e04\u0e2d\u0e23\u0e4c\u0e19 \u0e0a\u0e31\u0e49\u0e19 5 \u0e22\u0e39\u0e19\u0e34\u0e15 sh578 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569143270\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e38\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e27\u0e32\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569143270 \u0e1a\u0e08.\u0e17\u0e38\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e27\u0e32\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 123  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e31\u0e19\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e2a \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e2d \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 21 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e20\u0e32\u0e27\u0e14\u0e35\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569023479\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e42\u0e0b\u0e25\u0e34\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023479 \u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e42\u0e0b\u0e25\u0e34\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 151 \u0e16\u0e19\u0e19\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023533\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e2d\u0e1a\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e40\u0e14\u0e2d\u0e30\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023533 \u0e1a\u0e08.\u0e01\u0e2d\u0e1a\u0e28\u0e34\u0e25\u0e1b\u0e4c \u0e40\u0e14\u0e2d\u0e30\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 70201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e1d\u0e36\u0e01\u0e1d\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15(\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22)\u0e49\u0e48 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 33\/75  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e38\u0e18\u0e32\u0e23\u0e34\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 23 \u0e16\u0e19\u0e19\u0e04\u0e25\u0e2d\u0e07 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0163569000591\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e33\u0e1b\u0e31\u0e48\u0e19\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e22\u0e4c\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47511\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47511\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0163569000591 \u0e2b\u0e08.\u0e01\u0e33\u0e1b\u0e31\u0e48\u0e19\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e22\u0e4c 2569-07-31 100000 47511 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 139  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0345569003468\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e40\u0e23\u0e35\u0e22 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003468 \u0e1a\u0e08.\u0e42\u0e04\u0e40\u0e23\u0e35\u0e22 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1e\u0e33\u0e19\u0e31\u0e01 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u6559\u80b2 30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0745569008083\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e23\u0e27\u0e22\u0e14\u0e35 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569008083 \u0e1a\u0e08.\u0e40\u0e2e\u0e07\u0e23\u0e27\u0e22\u0e14\u0e35 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1b\u0e25\u0e32 \u0e01\u0e38\u0e49\u0e07 \u0e1b\u0e39 \u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e36\u0e01 \u0e2a\u0e32\u0e2b\u0e23\u0e48\u0e32\u0e22 \u0e2b\u0e2d\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013922\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08-\u0e27\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013922 \u0e1a\u0e08.\u0e40\u0e08-\u0e27\u0e35 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e1b\u0e34\u0e14\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 100\/428  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013949\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e19\u0e32 \u0e1f\u0e39\u0e40\u0e2d\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013949 \u0e1a\u0e08.\u0e21\u0e35\u0e19\u0e32 \u0e1f\u0e39\u0e40\u0e2d\u0e42\u0e01\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30 \u0e1a\u0e32\u0e23\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 63\/202  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010974\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e25\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e15\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010974 \u0e1a\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e25\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e15\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 100000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23  \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23  \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23  \u0e14\u0e39\u0e41\u0e25\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23  \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17  \u0e27\u0e34\u0e25\u0e25\u0e48\u0e32  \u0e1a\u0e31\u0e07\u0e01\u0e30\u0e42\u0e25  \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46   \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 166\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569142559\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e08 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86203\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86203\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142559 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e40\u0e08 \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25 \u0e40\u0e27\u0e25\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 100000 86203 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25 \u0e04\u0e25\u0e34\u0e19\u0e34\u0e01\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08 \u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e42\u0e23\u0e04\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1f\u0e31\u0e19 \u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e31\u0e19\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e15\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u533b\u7642\u30fb\u798f\u7949 136\/18  \u0e16\u0e19\u0e19\u0e19\u0e40\u0e23\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142737\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e19\u0e32 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142737 \u0e1a\u0e08.\u0e25\u0e31\u0e04\u0e19\u0e32 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 100000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 75\/8  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e04\u0e23\u0e34\u0e2a\u0e15\u0e31\u0e25 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002607\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 6245\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002607 \u0e2b\u0e08.\u0e23\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 6245 2569-07-30 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u5bbf\u6cca\u30fb\u98f2\u98df 987\/78  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0133569002674\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e34\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002674 \u0e2b\u0e08.\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e34\u0e23\u0e34\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 2569-07-30 100000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e22\u0e32 \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04 \u0e40\u0e20\u0e2a\u0e31\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e1b\u0e38\u0e4b\u0e22 \u0e22\u0e32\u0e1b\u0e23\u0e32\u0e1a\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e22\u0e32\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1e\u0e37\u0e0a\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569039501\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63120\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63120\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039501 \u0e1a\u0e08.\u0e22\u0e39\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e25\u0e34\u0e07\u0e01\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 100000 63120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 789\/3  \u0e2d\u0e32\u0e04\u0e32\u0e2320070687706 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569039528\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e29\u0e0e\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039528 \u0e1a\u0e08.\u0e2d\u0e31\u0e29\u0e0e\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 100000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u91d1\u878d\u30fb\u4fdd\u967a 198\/252  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0103569008176\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35.\u0e0b\u0e35. 51\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008176 \u0e2b\u0e08.\u0e14\u0e35.\u0e0b\u0e35. 51 2569-07-29 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 51  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 65\/1 \u0e41\u0e22\u0e01 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142389\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142389 \u0e1a\u0e08.\u0e41\u0e2d\u0e14\u0e27\u0e32\u0e19\u0e0b\u0e4c \u0e41\u0e21\u0e17\u0e17\u0e35\u0e40\u0e23\u0e35\u0e22\u0e25\u0e2a\u0e4c \u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 100000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e21\u0e35 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 477\/8  \u0e0b\u0e2d\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32 \u0e16\u0e19\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0215569010031\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569010031 \u0e1a\u0e08.\u0e40\u0e04\u0e2d\u0e32\u0e23\u0e4c\u0e27\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 5\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016835\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e17\u0e35 \u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016835 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e17\u0e35 \u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 100000 70209 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e01\u0e48\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 29  \u0e0b\u0e2d\u0e22 4 \u0e16\u0e19\u0e19\u0e2b\u0e31\u0e2a\u0e14\u0e34\u0e40\u0e2a\u0e27\u0e35 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569142303\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e25\u0e25\u0e47\u0e2d\u0e1b\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142303 \u0e1a\u0e08.\u0e41\u0e01\u0e25\u0e25\u0e47\u0e2d\u0e1b\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 100000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 254  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569142320\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e1e\u0e35\u0e0a\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142320 \u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e1e\u0e35\u0e0a\u0e41\u0e2a\u0e19\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e20\u0e32\u0e1e \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 622\/28  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569023355\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e27\u0e34\u0e42\u0e1b\u0e23\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023355 \u0e1a\u0e08.\u0e0b\u0e31\u0e19 \u0e27\u0e34\u0e42\u0e1b\u0e23\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 100000 47222 \u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e21\u0e14\u0e37\u0e48\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21             \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e0a\u0e39\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e02\u0e27\u0e14 \u0e19\u0e49\u0e33\u0e2d\u0e31\u0e14\u0e25\u0e21 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e01\u0e32\u0e41\u0e1f \u0e0a\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27            \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/53  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569004048\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e38\u0e49\u0e21 \u0e41\u0e2e\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96103\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96103\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569004048 \u0e1a\u0e08.\u0e2d\u0e38\u0e49\u0e21 \u0e41\u0e2e\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 100000 96103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32  \u0e15\u0e31\u0e14\u0e1c\u0e21  \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21  \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 210  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569005297\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e0b\u0e35168\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46510\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46510\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005297 \u0e2b\u0e08.\u0e1e\u0e35\u0e0b\u0e35168 2569-07-28 100000 46510 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e42\u0e19\u0e49\u0e15\u0e1a\u0e38\u0e4a\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 174\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001501\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e0b\u0e35\u0e48 \u0e40\u0e21\u0e25\u0e42\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10799\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10799\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001501 \u0e1a\u0e08.\u0e40\u0e14\u0e0b\u0e35\u0e48 \u0e40\u0e21\u0e25\u0e42\u0e25\u0e27\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 100000 10799 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e39\u0e1b \u0e40\u0e01\u0e29\u0e15\u0e01\u0e23\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e02\u0e49\u0e32\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14 \u88fd\u9020 113  \u0e2d\u0e32\u0e04\u0e32\u0e231  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 113 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 13 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e25\u0e48\u0e32 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0735569007656\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e42\u0e2e\u0e21 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-28\",\"reg_date_sort\":25690728,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007656 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e42\u0e2e\u0e21 \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-28 100000 47525 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0105569141897\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e19\u0e19 \u0e04\u0e31\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141897 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e19\u0e19 \u0e04\u0e31\u0e17  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 11\/44  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.9 \u0e0b\u0e2d\u0e22 47 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024858\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e14\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024858 \u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e14\u0e34 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 32111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07\u0e17\u0e33 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e17\u0e2d\u0e07 \u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u88fd\u9020 123\/788  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002321\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e01\u0e34\u0e14\u0e23\u0e31\u0e28\u0e21\u0e34\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002321 \u0e2b\u0e08.\u0e40\u0e01\u0e34\u0e14\u0e23\u0e31\u0e28\u0e21\u0e34\u0e4c 2569-07-27 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 196\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002658\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43299\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43299\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002658 \u0e2b\u0e08.\u0e17\u0e35\u0e1e\u0e35\u0e40\u0e2d \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 2569-07-27 100000 43299 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e40\u0e02\u0e49\u0e32-\u0e2d\u0e2d\u0e01 (access-control) \u0e07\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u5efa\u8a2d 111\/95  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e2a\u0e38\u0e02 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 1 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023240\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e40\u0e0b \u0e42\u0e1a\u0e17\u0e32\u0e19\u0e34\u0e04\u0e31\u0e25 \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"21001\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"21001\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023240 \u0e1a\u0e08.\u0e40\u0e21\u0e40\u0e0b \u0e42\u0e1a\u0e17\u0e32\u0e19\u0e34\u0e04\u0e31\u0e25 \u0e41\u0e21\u0e19\u0e39\u0e41\u0e1f\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 21001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e32\u0e41\u0e1c\u0e19\u0e44\u0e17\u0e22 \u0e22\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e2a\u0e21\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e2d\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e19\u0e2d\u0e01\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u88fd\u9020 4\/44  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023258\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1b\u0e27\u0e34\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023258 \u0e1a\u0e08.\u0e40\u0e2d\u0e1b\u0e27\u0e34\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e02\u0e2d\u0e07\u0e2a\u0e23\u0e23\u0e1e\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 4\/45  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023274\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023274 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e2d\u0e2a\u0e0b\u0e35 \u0e04\u0e2d\u0e19\u0e41\u0e17\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e02\u0e49\u0e2d\u0e15\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30 \u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e17\u0e32\u0e07\u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e19\u0e4d\u0e32\u0e41\u0e2a\u0e07\u0e08\u0e32\u0e19\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e15\u0e37\u0e2d\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e44\u0e1f\u0e16\u0e19\u0e19\u0e41\u0e25\u0e30 \u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e44\u0e1f\u0e44\u0e1f\u0e17\u0e32\u0e07\u0e27\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1c\u0e07\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u5efa\u8a2d 81\/120  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e38\u0e13\u0e11\u0e23\u0e34\u0e01 \u0e19\u0e34\u0e27\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569039137\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e21\u0e34\u0e15\u0e23 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039137 \u0e1a\u0e08.\u0e21\u0e2b\u0e32\u0e21\u0e34\u0e15\u0e23 \u0e1f\u0e39\u0e49\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/2  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e1e\u0e31\u0e12\u0e19\u0e32 1 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569004074\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e40\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569004074 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e04\u0e40\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0405569007284\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e0a\u0e32\u0e44\u0e19\u0e22 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007284 \u0e1a\u0e08.\u0e2d\u0e32\u0e0a\u0e32\u0e44\u0e19\u0e22 \u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e4d\u0e32\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar rooftop) \u0e2a\u0e4d\u0e32\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e4d\u0e32\u0e23\u0e27\u0e08\u0e2b\u0e19\u0e49\u0e32\u0e07\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e34\u0e25\u0e04\u0e48\u0e32\u0e44\u0e1f \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e4d\u0e32\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e01 \u0e17\u0e4d\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e1c\u0e07\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u5efa\u8a2d 528  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0425569000611\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e17 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0425569000611 \u0e1a\u0e08.\u0e1a\u0e35\u0e40\u0e2d\u0e17 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 8\/6  \u0e16\u0e19\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0653569001223\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e1e\u0e2a\u0e4c\u0e17 \u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81293\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81293\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001223 \u0e2b\u0e08.\u0e40\u0e08\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e1e\u0e2a\u0e4c\u0e17 \u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25 2569-07-27 100000 81293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e41\u0e21\u0e25\u0e07 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e23\u0e1a\u0e01\u0e27\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e21\u0e25\u0e07 \u0e23\u0e31\u0e1a\u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e1b\u0e25\u0e27\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e32\u0e23\u0e40\u0e04\u0e21\u0e35 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e41\u0e21\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e23\u0e1a\u0e01\u0e27\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 459\/947  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e34\u0e19\u0e25\u0e32\u0e20 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 17 \u0e16\u0e19\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0733569001133\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e32\u0e22\u0e1f\u0e49\u0e32 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001133 \u0e2b\u0e08.\u0e1b\u0e23\u0e32\u0e22\u0e1f\u0e49\u0e32 \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c 2569-07-27 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0735569007613\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e17\u0e23\u0e31\u0e04\u0e2a\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007613 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e17\u0e23\u0e31\u0e04\u0e2a\u0e4c \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u904b\u8f38\u30fb\u7269\u6d41 59\/43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0835569013817\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e2d\u0e25 \u0e0b\u0e35\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96109\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96109\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013817 \u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e2d\u0e25 \u0e0b\u0e35\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 96109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e34\u0e19\u0e34\u0e04\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e1a\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e23\u0e27\u0e21 \u0e42\u0e14\u0e22\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e40\u0e01\u0e34\u0e14\u0e42\u0e23\u0e04 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 476  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e19\u0e17\u0e23 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0905569006330\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e32\u0e40\u0e23\u0e35\u0e22 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006330 \u0e1a\u0e08.\u0e14\u0e32\u0e40\u0e23\u0e35\u0e22 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 100000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e44\u0e01\u0e48 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 103\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0103569008109\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e17\u0e04-\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e44\u0e2d\u0e17\u0e35 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008109 \u0e2b\u0e08.\u0e40\u0e17\u0e04-\u0e42\u0e1f\u0e25\u0e27\u0e4c \u0e44\u0e2d\u0e17\u0e35 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c 2569-07-26 100000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 (it) \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/112  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e19\u0e31\u0e19\u0e18\u0e23 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1d\u0e31\u0e48\u0e07\u0e43\u0e15\u0e49 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569141251\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e2a\u0e38\u0e18\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141251 \u0e1a\u0e08.\u0e27\u0e2a\u0e38\u0e18\u0e32 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 100000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 188\/29  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0215569009955\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009955 \u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 100\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e19\u0e40\u0e17\u0e08 3 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569141137\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e25\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e0b\u0e4c \u0e14\u0e34\u0e2a\u0e40\u0e1e\u0e19\u0e0b\u0e32\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141137 \u0e1a\u0e08.\u0e1e\u0e34\u0e25\u0e2a\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e25\u0e25\u0e34\u0e40\u0e08\u0e19\u0e0b\u0e4c \u0e14\u0e34\u0e2a\u0e40\u0e1e\u0e19\u0e0b\u0e32\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 100000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c  \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34  \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 58  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e42\u0e21\u0e17\u0e22\u0e4c 2 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e23\u0e27\u0e07\u0e27\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024769\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10711\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10711\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024769 \u0e1a\u0e08.\u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e25\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 100000 10711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e19\u0e21\u0e1b\u0e31\u0e07 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 186\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024785\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e41\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024785 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04\u0e41\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 100000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (holding company) \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e25\u0e07\u0e17\u0e38\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u91d1\u878d\u30fb\u4fdd\u967a 1\/9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e2d\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e01\u0e2d\u0e25\u0e4c\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e31\u0e19\u0e17\u0e23\u0e35 \u0e04\u0e25\u0e31\u0e1a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1e\u0e48\u0e07 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569023100\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e1f \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023100 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d\u0e1f \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 100000 22299 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c ai art toy 3d design \u0e2b\u0e23\u0e37\u0e2d product design \u88fd\u9020 173\/6  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e0125\u0e0b\u0e2d\u0e224 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569039056\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569039056 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a \u0e0b\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 100000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e07\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 153\/58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0403569003317\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e40\u0e21\u0e18\u0e32\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10771\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10771\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003317 \u0e2b\u0e08.\u0e42\u0e0a\u0e15\u0e34\u0e40\u0e21\u0e18\u0e32 2569-07-25 100000 10771 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u88fd\u9020 10  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e42\u0e0a\u0e15\u0e34\u0e40\u0e21\u0e18\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e17\u0e38\u0e48\u0e07\u0e21\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0403569003325\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"03221\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"03221\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003325 \u0e2b\u0e08.\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32 2569-07-25 100000 03221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u8fb2\u6797\u6c34\u7523 428  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005254\",\"name_th\":\"\u0e2b\u0e08.\u0e1f\u0e1e.\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005254 \u0e2b\u0e08.\u0e1f\u0e1e.\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-25 100000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e25\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e27\u0e07\u0e08\u0e23\u0e1b\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e01\u0e49\u0e44\u0e02\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 83\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0565569000688\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e27\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000688 \u0e1a\u0e08.\u0e1f\u0e32\u0e27\u0e14\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 100000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15 \u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 (oem\/odm) \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e49\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e49\u0e32\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 416  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0903569001786\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e2e\u0e21\u0e21\u0e35\u0e48 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001786 \u0e2b\u0e08.\u0e42\u0e2e\u0e21\u0e21\u0e35\u0e48 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e19\u0e17\u0e4c 2569-07-25 100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 389\/55  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0955569000617\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000617 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e21\u0e2d\u0e32\u0e23\u0e4c \u0e42\u0e21\u0e1a\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-25 100000 77109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e16\u0e40\u0e0a\u0e48\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 176\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569139761\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e21\u0e1e\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139761 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e21\u0e1e\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 332\/376  \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140408\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e32 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140408 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e15\u0e23\u0e32 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 64201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u91d1\u878d\u30fb\u4fdd\u967a 1126\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e32\u0e19\u0e34\u0e0a 2 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 27 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140491\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e25\u0e0a\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140491 \u0e1a\u0e08.\u0e41\u0e25\u0e0a\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e43\u0e1a\u0e2b\u0e19\u0e49\u0e32 \u0e02\u0e19\u0e15\u0e32\u0e1b\u0e25\u0e2d\u0e21  \u0e02\u0e19\u0e15\u0e32\u0e21\u0e35\u0e01\u0e32\u0e27 \u0e01\u0e32\u0e27\u0e15\u0e34\u0e14\u0e02\u0e19\u0e15\u0e32 \u0e19\u0e49\u0e33\u0e22\u0e32\u0e16\u0e2d\u0e14\u0e01\u0e32\u0e27\u0e02\u0e19\u0e15\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/184  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140688\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e42\u0e2d\u0e40\u0e2d\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140688 \u0e1a\u0e08.\u0e40\u0e2d\u0e42\u0e2d\u0e40\u0e2d\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 7  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0b\u0e31\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e1e\u0e2d\u0e22\u0e17\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 148 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 69 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140823\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e32\u0e21\u0e38\u0e19\u0e17\u0e32\u0e19\u0e32 \u0e44\u0e2e \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140823 \u0e1a\u0e08.\u0e15\u0e23\u0e32\u0e21\u0e38\u0e19\u0e17\u0e32\u0e19\u0e32 \u0e44\u0e2e \u0e04\u0e25\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e04\u0e32\u0e40\u0e1f\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 (catering service) \u5bbf\u6cca\u30fb\u98f2\u98df 142  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e39 \u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 \u0e40\u0e1e\u0e25\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1705 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140858\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e33\u0e14\u0e35\u0e17\u0e27\u0e35\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140858 \u0e1a\u0e08.\u0e17\u0e33\u0e14\u0e35\u0e17\u0e27\u0e35\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 85499 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u6559\u80b2 210\/33  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569140891\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e04\u0e19\u0e4c\u0e14\u0e30\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569140891 \u0e1a\u0e08.\u0e44\u0e04\u0e19\u0e4c\u0e14\u0e30\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e15\u0e32\u0e07\u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/169  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 37 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027831\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e32\u0e22\u0e08\u0e35\u0e42\u0e19\u0e21\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74909\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74909\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027831 \u0e1a\u0e08.\u0e1f\u0e32\u0e22\u0e08\u0e35\u0e42\u0e19\u0e21\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 74909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e42\u0e23\u0e04\u0e20\u0e31\u0e22\u0e44\u0e02\u0e49\u0e40\u0e08\u0e47\u0e1a \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 56  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 8 \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027890\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e31\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e4a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027890 \u0e1a\u0e08.\u0e1a\u0e31\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e4a\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e31\u0e1a\u0e2d\u0e1a\u0e23\u0e21 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 129\/206  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e40\u0e1f\u0e04\u0e40\u0e1e\u0e25\u0e2a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022839\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e1a\u0e38\u0e0d \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022839 \u0e1a\u0e08.\u0e21\u0e35\u0e1a\u0e38\u0e0d \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2a\u0e31\u0e07\u0e06\u0e17\u0e32\u0e19 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e42\u0e1b\u0e23\u0e22\u0e17\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e17\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 101\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022847\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e23\u0e25\u0e25\u0e34\u0e07 \u0e2a\u0e15\u0e23\u0e2d\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022847 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e23\u0e25\u0e25\u0e34\u0e07 \u0e2a\u0e15\u0e23\u0e2d\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 73101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e31\u0e15\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e35\u0e17\u0e31\u0e0a\u0e20\u0e32\u0e1e\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 65\/144  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e2a\u0e15\u0e49\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e42\u0e0b\u0e19 \u0e0b\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e21 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022871\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e4a\u0e32\u0e2a\u0e4c\u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022871 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e4a\u0e32\u0e2a\u0e4c\u0e42\u0e1b\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u533b\u7642\u30fb\u798f\u7949 9\/99  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e22\u0e32\u0e21\u0e44\u0e2e\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e01\u0e38\u0e0d\u0e0a\u0e23 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022944\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e28\u0e30\u0e22\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e27\u0e25\u0e18\u0e4c168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022944 \u0e1a\u0e08.\u0e28\u0e28\u0e30\u0e22\u0e32\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e40\u0e27\u0e25\u0e18\u0e4c168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1211  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569023088\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e17\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43221\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43221\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023088 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e17\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 43221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 79\/264  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004881\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e1f \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004881 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e1f \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569038874\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e08\u0e19\u0e4c \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038874 \u0e1a\u0e08.\u0e2a\u0e38\u0e1e\u0e08\u0e19\u0e4c \u0e40\u0e1e\u0e32\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 43909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e07\u0e32\u0e19\u0e17\u0e48\u0e2d\u0e25\u0e21\u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2b\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1b\u0e39\u0e19\u0e17\u0e33\u0e1e\u0e37\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u5efa\u8a2d 29  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038980\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e1a\u0e21\u0e38\u0e21 50 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038980 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e1a\u0e21\u0e38\u0e21 50 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 50  \u0e0b\u0e2d\u0e22 1 (\u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19-\u0e2d\u0e48\u0e32\u0e07\u0e28\u0e34\u0e25\u0e32) \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569009866\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e08 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45201\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45201\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009866 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e08 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 45201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e39\u0e48\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e25\u0e49\u0e32\u0e07\u0e23\u0e16 \u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a\u0e2a\u0e35 \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e16\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e14\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 119\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009921\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e48888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46495\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46495\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009921 \u0e1a\u0e08.\u0e2d\u0e35\u0e0b\u0e35\u0e48888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 46495 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 49\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0305569007668\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e2d\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01629\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01629\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007668 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e2d\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e04\u0e44\u0e19\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 01629 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1d\u0e36\u0e01 \u0e2a\u0e2d\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e38\u0e19\u0e31\u0e02 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2a\u0e38\u0e19\u0e31\u0e02\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e04\u0e38\u0e21\u0e2a\u0e38\u0e19\u0e31\u0e02\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e21\u0e01\u0e25\u0e34\u0e48\u0e19 \u8fb2\u6797\u6c34\u7523 988\/100  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0335569001180\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e21\u0e25\u0e34\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0335569001180 \u0e1a\u0e08.\u0e2d\u0e31\u0e21\u0e25\u0e34\u0e0b\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e23\u0e30\u0e15\u0e48\u0e32\u0e22\u0e14\u0e48\u0e2d\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0345569003409\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e04\u0e2a\u0e15\u0e31\u0e25\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003409 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e04\u0e2a\u0e15\u0e31\u0e25\u0e01\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 55101 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u5bbf\u6cca\u30fb\u98f2\u98df 127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0395569000477\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000477 \u0e1a\u0e08.\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 246  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0505569016614\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016614 \u0e1a\u0e08.\u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 58202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b (saas)  \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 499\/202  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e04\u0e30\u0e22\u0e2d\u0e21(\u0e28\u0e34\u0e23\u0e34\u0e1e\u0e23) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 16 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0603569001720\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001720 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 2569-07-24 100000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16 \u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 118  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0605569002183\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e0b\u0e4c\u0e25\u0e34\u0e2a \u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 94 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14111\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14111\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002183 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e0b\u0e4c\u0e25\u0e34\u0e2a \u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 94 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 14111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u88fd\u9020 999\/227  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e2d\u0e0b\u0e4c\u0e41\u0e25\u0e19\u0e14\u0e4c5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0653569001215\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 19\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47999\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47999\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0653569001215 \u0e2b\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 19 2569-07-24 100000 47999 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\\\"\\\" \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0735569007508\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e30 \u0e1e\u0e47\u0e2d\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007508 \u0e1a\u0e08.\u0e40\u0e21\u0e01\u0e30 \u0e1e\u0e47\u0e2d\u0e15 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01 \u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15  (\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\/e-commerce) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 199\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007923\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e2a\u0e37\u0e1a\u0e44\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007923 \u0e1a\u0e08.\u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e2a\u0e37\u0e1a\u0e44\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u904b\u8f38\u30fb\u7269\u6d41 121\/215  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0835569013744\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e25\u0e2d\u0e07\u0e08\u0e34\u0e27\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013744 \u0e1a\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e25\u0e2d\u0e07\u0e08\u0e34\u0e27\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 100000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e23\u0e31\u0e1a-\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 476  \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e19\u0e17\u0e23 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569007919\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e23\u0e27\u0e22 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007919 \u0e2b\u0e08.\u0e27\u0e35\u0e23\u0e27\u0e22 \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b 2569-07-23 100000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e40\u0e1b\u0e47\u0e23\u0e01\u0e32\u0e23\u0e40\u0e09\u0e1e\u0e32\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/8  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e23\u0e34\u0e2a\u0e41\u0e04\u0e27\u0e23\u0e4c \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 80 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138527\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e34\u0e0a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138527 \u0e1a\u0e08.\u0e27\u0e35\u0e23\u0e34\u0e0a \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 359\/213  \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138535\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e1e\u0e35 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138535 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e25 \u0e1e\u0e35 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 52\/36  \u0e0b\u0e2d\u0e22 \u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 52 \u0e41\u0e22\u0e01 44 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139124\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e34\u0e19\u0e2d\u0e31\u0e1e \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139124 \u0e1a\u0e08.\u0e1e\u0e34\u0e19\u0e2d\u0e31\u0e1e \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 224\/43  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e23\u0e32\u0e0d\u0e2a\u0e34\u0e23\u0e34 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 1 \u0e0b\u0e2d\u0e22 10 \u0e16\u0e19\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139213\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e25\u0e2d\u0e27\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139213 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e1e\u0e35 \u0e25\u0e2d\u0e27\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e43\u0e19\u0e28\u0e32\u0e25 \u0e08\u0e31\u0e14\u0e17\u0e33\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23 \u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e17\u0e31\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1000\/9  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e2a \u0e27\u0e34\u0e0a\u0e31\u0e19\u0e19\u0e32\u0e23\u0e35 \u0e1b\u0e32\u0e23\u0e4c\u0e04 - \u0e40\u0e0b\u0e32\u0e18\u0e4c \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 1210a \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139230\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e40\u0e27\u0e2a\u0e15\u0e4c \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52239\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52239\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139230 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e40\u0e27\u0e2a\u0e15\u0e4c \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 52239 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27 \u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u904b\u8f38\u30fb\u7269\u6d41 8\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e1f\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 502 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e41\u0e27\u0e19\u0e15\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569139523\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569139523 \u0e1a\u0e08.\u0e14\u0e23\u0e35\u0e21.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e25\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19 \u82b8\u8853\u30fb\u5a2f\u697d 39\/3  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1b\u0e25\u0e32\u0e40\u0e04\u0e49\u0e32 34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0123569002305\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002305 \u0e2b\u0e08.\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48 2569-07-23 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c 32 \u0e41\u0e22\u0e01 4 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027741\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e1e\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90001\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90001\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027741 \u0e1a\u0e08.\u0e20\u0e1e\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 90001 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u82b8\u8853\u30fb\u5a2f\u697d 99\/77  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e25\u0e25\u0e14\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022821\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022821 \u0e1a\u0e08.\u0e1e\u0e35 \u0e40\u0e2d\u0e47\u0e19 \u0e1e\u0e35 \u0e1f\u0e34\u0e27\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e17\u0e22 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e20\u0e32\u0e22\u0e43\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e21\u0e35\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 37\/238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004822\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"20232\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"20232\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004822 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e44\u0e19\u0e0b\u0e4c \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 20232 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e0b\u0e25\u0e31\u0e48\u0e21\u0e1b\u0e25\u0e39\u0e01\u0e1c\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 19\/139  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0165569001734\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85493\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85493\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001734 \u0e1a\u0e08.\u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e40\u0e2d\u0e47\u0e14\u0e14\u0e39\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 85493 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27 \u0e01\u0e32\u0e23\u0e15\u0e34\u0e27\u0e2a\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23  \u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e20\u0e32\u0e29\u0e32 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e14\u0e19\u0e15\u0e23\u0e35 \u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e01\u0e35\u0e2c\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u6559\u80b2 374\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0183569000281\",\"name_th\":\"\u0e2b\u0e08.\u0e13\u0e38\u0e14\u0e32 \u0e40\u0e04\u0e25\u0e48\u0e32 \u0e04\u0e34\u0e14\u0e2a\u0e4c\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0183569000281 \u0e2b\u0e08.\u0e13\u0e38\u0e14\u0e32 \u0e40\u0e04\u0e25\u0e48\u0e32 \u0e04\u0e34\u0e14\u0e2a\u0e4c 2569-07-23 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0193569000825\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82911\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82911\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000825 \u0e2b\u0e08.\u0e40\u0e2d\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-23 100000 82911 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038718\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e09\u0e34\u0e19 \u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038718 \u0e1a\u0e08.\u0e40\u0e09\u0e34\u0e19 \u0e1e\u0e32\u0e23\u0e27\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 899\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0275569001164\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e1e\u0e31\u0e15\u0e23\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001164 \u0e1a\u0e08.\u0e2d\u0e20\u0e34\u0e1e\u0e31\u0e15\u0e23\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 69100 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e04\u0e14\u0e35 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e25\u0e30\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u0e23\u0e31\u0e1a\u0e2a\u0e37\u0e1a\u0e2a\u0e27\u0e19 \u0e2a\u0e2d\u0e1a\u0e2a\u0e27\u0e19 \u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1e\u0e24\u0e15\u0e34\u0e01\u0e23\u0e23\u0e21\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e43\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e33\u0e19\u0e27\u0e19\u0e04\u0e14\u0e35 \u0e40\u0e23\u0e48\u0e07\u0e23\u0e31\u0e14\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2b\u0e19\u0e35\u0e49\u0e2a\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e42\u0e08\u0e17\u0e01\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e0a\u0e48\u0e27\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e02\u0e4c \u0e1f\u0e49\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e07 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35 \u0e41\u0e01\u0e49\u0e15\u0e48\u0e32\u0e07\u0e04\u0e14\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e49\u0e2d\u0e1e\u0e34\u0e1e\u0e32\u0e17\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e43\u0e19\u0e28\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e2d\u0e01\u0e28\u0e32\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e43\u0e14\u0e46\u0e1b\u0e23\u0e30\u0e19\u0e35\u0e1b\u0e23\u0e30\u0e19\u0e2d\u0e21\u0e22\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e43\u0e14\u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 55\/5  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e2535 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0405569007071\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e48\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569007071 \u0e1a\u0e08.\u0e41\u0e01\u0e48\u0e19 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 47691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e07\u0e32\u0e19\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c \u0e08\u0e34\u0e27\u0e40\u0e27\u0e25\u0e23\u0e35\u0e48 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0473569000997\",\"name_th\":\"\u0e2b\u0e08.\u0e02\u0e27\u0e31\u0e0d\u0e43\u0e08 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e1f\u0e39\u0e49\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0473569000997 \u0e2b\u0e08.\u0e02\u0e27\u0e31\u0e0d\u0e43\u0e08 \u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e1f\u0e39\u0e49\u0e14 2569-07-23 100000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e21\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e0a\u0e33\u0e41\u0e2b\u0e25\u0e30 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 127  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e01\u0e25\u0e19\u0e04\u0e23 \u30b5\u30b3\u30f3\u30ca\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569005157\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e2a\u0e40\u0e1b\u0e0b\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005157 \u0e2b\u0e08.\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32 \u0e2a\u0e40\u0e1b\u0e0b 2569-07-23 100000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (vending machine) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016550\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e1f\u0e25\u0e27\u0e4c 24 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016550 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21 \u0e42\u0e1f\u0e25\u0e27\u0e4c 24 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34 \u60c5\u5831\u901a\u4fe1\u30fbit 2\/5  \u0e16\u0e19\u0e19\u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016568\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e42\u0e2b\u0e23\u0e35 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016568 \u0e1a\u0e08.\u0e21\u0e42\u0e2b\u0e23\u0e35 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e33\u0e2b\u0e19\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016584\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1f\u0e40\u0e17\u0e25\u0e34\u0e01\u0e0b\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01289\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01289\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016584 \u0e1a\u0e08.\u0e44\u0e1f\u0e40\u0e17\u0e25\u0e34\u0e01\u0e0b\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 100000 01289 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e49\u0e33\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e14\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e15\u0e32\u0e21\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01 \u0e0a\u0e19\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u8fb2\u6797\u6c34\u7523 7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0603569001703\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e2d\u0e35\u0e27\u0e35\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35102\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35102\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001703 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e27\u0e31\u0e19 \u0e2d\u0e35\u0e27\u0e35 2569-07-23 100000 35102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e2d\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e44\u0e1f\u0e1f\u0e49\u0e32 (ev charging station) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e1b\u0e25\u0e31\u0e4a\u0e01\u0e2d\u0e34\u0e19\u0e44\u0e2e\u0e1a\u0e23\u0e34\u0e14 (phev)  \u0e41\u0e25\u0e30\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 (bev) \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 299\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0843569001434\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e27\u0e4c\u0e1f\u0e23\u0e38\u0e15 \u0e40\u0e17\u0e23\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01222\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01222\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001434 \u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e27\u0e4c\u0e1f\u0e23\u0e38\u0e15 \u0e40\u0e17\u0e23\u0e14 2569-07-23 100000 01222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2a\u0e27\u0e19\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e40\u0e1e\u0e32\u0e30\u0e1b\u0e25\u0e39\u0e01\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u8fb2\u6797\u6c34\u7523 71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569137776\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e1e\u0e35\u0e40\u0e1e\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137776 \u0e1a\u0e08.\u0e41\u0e21\u0e17\u0e40\u0e17\u0e2d\u0e23\u0e4c \u0e1e\u0e35\u0e40\u0e1e\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 111\/58  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e23\u0e35\u0e22\u0e32\u0e41\u0e2d\u0e17\u0e42\u0e2e\u0e21 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 29 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e21\u0e19\u0e39\u0e01\u0e34\u0e08 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137792\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e08\u0e35 \u0e40\u0e1a\u0e2a\u0e15\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137792 \u0e1a\u0e08.\u0e42\u0e2d\u0e08\u0e35 \u0e40\u0e1a\u0e2a\u0e15\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 73101 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32: \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (digital advertising) \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (social media marketing) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 491\/16  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2e\u0e32\u0e1a\u0e34\u0e40\u0e17\u0e35\u0e22\u0e44\u0e25\u0e19\u0e4c \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137831\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e40\u0e18\u0e2d\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137831 \u0e1a\u0e08.\u0e23\u0e31\u0e01\u0e40\u0e18\u0e2d\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 395\/478  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 \u0e17\u0e32\u0e27\u0e19\u0e4c \u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07-\u0e09\u0e25\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07 \u0e16\u0e19\u0e19\u0e09\u0e25\u0e2d\u0e07\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137873\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e08\u0e25\u0e35\u0e19\u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137873 \u0e1a\u0e08.\u0e42\u0e08\u0e25\u0e35\u0e19\u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u60c5\u5831\u901a\u4fe1\u30fbit 98\/48  \u0e2d\u0e32\u0e04\u0e32\u0e23ds tower i \u0e0b\u0e2d\u0e22 \u0e53\u0e53 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137881\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2e\u0e21\u0e41\u0e25\u0e47\u0e1a \u0e1a\u0e34\u0e25\u0e17\u0e4c\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137881 \u0e1a\u0e08.\u0e42\u0e2e\u0e21\u0e41\u0e25\u0e47\u0e1a \u0e1a\u0e34\u0e25\u0e17\u0e4c\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 64\/127  \u0e0b\u0e2d\u0e22 9 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137920\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137920 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e1f\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e23\u0e35\u0e44\u0e1f\u0e41\u0e19\u0e19\u0e0b\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e42\u0e14\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e39\u0e49 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e15\u0e49\u0e19\u0e08\u0e19\u0e08\u0e1a\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e40\u0e40\u0e17\u0e19\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 118\/1  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e34\u0e1b\u0e42\u0e01\u0e49 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c 1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137997\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137997 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49 \u0e40\u0e2e\u0e25\u0e17\u0e4c\u0e15\u0e35\u0e49 \u0e25\u0e31\u0e04\u0e01\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e20\u0e32\u0e1e\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21  \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 218  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e1a\u0e2d\u0e19 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569138292\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1f\u0e19\u0e4c \u0e40\u0e14\u0e22\u0e4c\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569138292 \u0e1a\u0e08.\u0e44\u0e1f\u0e19\u0e4c \u0e40\u0e14\u0e22\u0e4c\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 86  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 110 \u0e41\u0e22\u0e01 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024173\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e0b\u0e39\u0e23\u0e34\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82301\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82301\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024173 \u0e1a\u0e08.\u0e40\u0e08 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e0b\u0e39\u0e23\u0e34\u0e21\u0e34 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 82301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 234\/238  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024203\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e21\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e1a\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024203 \u0e1a\u0e08.\u0e14\u0e21\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e1a\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 (delivery) \u5bbf\u6cca\u30fb\u98f2\u98df 48\/11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569024271\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024271 \u0e1a\u0e08.\u0e40\u0e2b\u0e15\u0e38\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e38\u0e02 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95\/113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002291\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e24\u0e29\u0e0f\u0e32 \u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002291 \u0e2b\u0e08.\u0e01\u0e24\u0e29\u0e0f\u0e32 \u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-22 100000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22-\u0e23\u0e30\u0e1a\u0e1a\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e25\u0e1a \u0e41\u0e23\u0e07\u0e14\u0e31\u0e19\u0e1a\u0e27\u0e01 \u0e23\u0e31\u0e1a\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e01 \u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 168\/131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027571\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e27\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027571 \u0e1a\u0e08.\u0e28\u0e23\u0e35\u0e27\u0e32 \u0e04\u0e2d\u0e23\u0e4c\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u6559\u80b2 129\/177  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002607\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04 \u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43223\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43223\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002607 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e04 \u0e41\u0e2d\u0e23\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-22 100000 43223 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e2d\u0e23\u0e4c \u0e25\u0e49\u0e32\u0e07\u0e41\u0e2d\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u5efa\u8a2d 98\/94  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0b\u0e34\u0e15\u0e35\u0e49\u0e40\u0e0b\u0e19\u0e2a\u0e4c \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022570\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022570 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e40\u0e2d\u0e2a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 71102 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\/\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 81\/91  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e4c\u0e27\u0e32\u0e23\u0e35 \u0e40\u0e1f\u0e2a 7 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022651\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e10\u0e21\u0e19 \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022651 \u0e1a\u0e08.\u0e13\u0e10\u0e21\u0e19 \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 188\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022685\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e25\u0e34\u0e21\u0e34\u0e15 888 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022685 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e25\u0e34\u0e21\u0e34\u0e15 888 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e02\u0e32\u0e22\u0e0b\u0e34\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168\/105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0153569000159\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e08\u0e23\u0e31\u0e2a 999\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46103\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46103\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07\",\"province_ja\":\"\u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\",\"search_text\":\"0153569000159 \u0e2b\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e08\u0e23\u0e31\u0e2a 999 2569-07-22 100000 46103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e0a\u0e31\u0e49\u0e19\u0e43\u0e19 \u0e0a\u0e38\u0e14\u0e1b\u0e23\u0e31\u0e1a\u0e2a\u0e23\u0e35\u0e23\u0e30 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2d\u0e48\u0e32\u0e07\u0e17\u0e2d\u0e07 \u30a2\u30fc\u30f3\u30c8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0555569000629\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e2a\u0e21\u0e38\u0e19\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e0a\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000629 \u0e1a\u0e08.\u0e2a\u0e27\u0e19\u0e2a\u0e21\u0e38\u0e19\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e0a\u0e31\u0e22 \u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e16\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e07 \u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e14 \u0e46 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 468-469  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e21\u0e19\u0e40\u0e17\u0e27\u0e23\u0e32\u0e0a \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0575569004764\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e34\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004764 \u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e08\u0e34\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 311\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e01\u0e25\u0e32\u0e07\u0e40\u0e27\u0e35\u0e22\u0e07 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0745569007737\",\"name_th\":\"\u0e1a\u0e08.1688 \u0e2d\u0e34\u0e07\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85491\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85491\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007737 \u0e1a\u0e08.1688 \u0e2d\u0e34\u0e07\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 85491 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2a\u0e2d\u0e19\u0e20\u0e32\u0e29\u0e32 \u0e01\u0e27\u0e14\u0e27\u0e34\u0e0a\u0e32 \u6559\u80b2 1600\/24  \u0e16\u0e19\u0e19\u0e19\u0e23\u0e23\u0e32\u0e0a\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0845569010770\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010770 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e21\u0e38\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 100000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e21\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 35\/14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569137458\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19 \u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137458 \u0e1a\u0e08.\u0e21\u0e2d\u0e23\u0e4c\u0e41\u0e01\u0e19 \u0e1f\u0e34\u0e25\u0e34\u0e1b\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 92  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e40\u0e0b\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3509 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569137466\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e44\u0e2e\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569137466 \u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e44\u0e2e\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 ( information technology consulting) \u60c5\u5831\u901a\u4fe1\u30fbit 64\/23  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569038084\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e32\u0e17\u0e4c\u0e0b\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038084 \u0e1a\u0e08.\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e2d\u0e32\u0e17\u0e4c\u0e0b\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 78300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19 (outsource) \u0e17\u0e31\u0e49\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27  \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e08\u0e49\u0e32\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23  \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 185\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e27\u0e31\u0e07\u0e2b\u0e34\u0e19 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569038246\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e40\u0e1f\u0e2a\u0e15\u0e4c\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569038246 \u0e1a\u0e08.\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e40\u0e1f\u0e2a\u0e15\u0e4c\u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 6\/119  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007536\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e32 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007536 \u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e32 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e2a\u0e37\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e04\u0e21\u0e40\u0e1b\u0e0d \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 548  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0415569003866\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e2d\u0e19\u0e19\u0e35\u0e48 \u0e0a\u0e2d\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003866 \u0e1a\u0e08.\u0e1a\u0e2d\u0e19\u0e19\u0e35\u0e48 \u0e0a\u0e2d\u0e22 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569005084\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e27\u0e35 2026\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005084 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e27\u0e35 2026 2569-07-21 100000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 179\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016452\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e04\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016452 \u0e1a\u0e08.\u0e42\u0e04\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 47411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a\u0e42\u0e0b\u0e23\u0e35\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 26\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0745569007656\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e42\u0e15\u0e23\u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85493\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85493\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007656 \u0e1a\u0e08.\u0e41\u0e2d\u0e2a\u0e42\u0e15\u0e23\u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 100000 85493 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u6559\u80b2 1\/71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0843569001426\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e25\u0e39\u0e21\u0e34 \u0e41\u0e25\u0e47\u0e1a\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001426 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e08 \u0e25\u0e39\u0e21\u0e34 \u0e41\u0e25\u0e47\u0e1a 2569-07-21 100000 47723 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e04\u0e23\u0e35\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e2a\u0e01\u0e34\u0e19\u0e41\u0e04\u0e23\u0e4c\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 71  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569136036\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e21\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e01\u0e39\u0e4a\u0e14 \u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136036 \u0e1a\u0e08.\u0e0b\u0e34\u0e21\u0e40\u0e1b\u0e34\u0e49\u0e25 \u0e01\u0e39\u0e4a\u0e14 \u0e40\u0e14\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1f\u0e37\u0e49\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e25\u0e32\u0e22\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14 \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32 \u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07 \u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5bbf\u6cca\u30fb\u98f2\u98df 1\/131  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 20 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e04\u0e25\u0e2d\u0e07\u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136133\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e2a\u0e40\u0e17\u0e19\u0e4c\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74902\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74902\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136133 \u0e1a\u0e08.\u0e0b\u0e31\u0e2a\u0e40\u0e17\u0e19\u0e4c\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 74902 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 156\/2  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136346\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e41\u0e1f\u0e04\u0e17\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64201\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64201\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136346 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e41\u0e1f\u0e04\u0e17\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 64201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07 \u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e2b\u0e38\u0e49\u0e19 \u0e2b\u0e38\u0e49\u0e19\u0e01\u0e39\u0e49 \u0e1e\u0e31\u0e19\u0e18\u0e1a\u0e31\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e14\u0e46  \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 (holding company) \u91d1\u878d\u30fb\u4fdd\u967a 2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e08\u0e31\u0e2a\u0e21\u0e34\u0e19  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 \u0e1a\u0e35 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 26 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e21\u0e34\u0e15\u0e23(\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136362\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e0a\u0e34\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136362 \u0e1a\u0e08.\u0e2d\u0e0a\u0e34\u0e23\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e15\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1044\/10  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 101 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136575\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e14\u0e31\u0e19\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136575 \u0e1a\u0e08.\u0e1f\u0e49\u0e32\u0e14\u0e31\u0e19\u0e40\u0e01\u0e25\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e1b\u0e01\u0e15\u0e34 \u6559\u80b2 110   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3-35 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 66\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136613\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e1e\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136613 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e1e\u0e35 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 37\/2  \u0e16\u0e19\u0e19\u0e28\u0e32\u0e25\u0e32\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136621\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e49\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77299\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77299\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136621 \u0e1a\u0e08.\u0e40\u0e1a\u0e2a\u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e23\u0e49\u0e19\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 77299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e0a\u0e38\u0e14\u0e23\u0e32\u0e15\u0e23\u0e35 \u0e0a\u0e38\u0e14\u0e2a\u0e01\u0e35 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1642-1644  \u0e16\u0e19\u0e19\u0e17\u0e23\u0e07\u0e27\u0e32\u0e14 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136630\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e35\u0e40\u0e1f\u0e25\u0e01\u0e0a\u0e31\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136630 \u0e1a\u0e08.\u0e23\u0e35\u0e40\u0e1f\u0e25\u0e01\u0e0a\u0e31\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 (workshop) \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u6559\u80b2 10  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 16 \u0e41\u0e22\u0e01 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136753\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 999 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136753 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 999 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 348  \u0e0b\u0e2d\u0e22 \u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023886\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e0a\u0e31\u0e22 1980 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49334\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49334\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023886 \u0e1a\u0e08.\u0e21\u0e07\u0e04\u0e25\u0e0a\u0e31\u0e22 1980 \u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 49334 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 22\/15  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569027288\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e33\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027288 \u0e1a\u0e08.\u0e17\u0e33\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 89\/1411  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027351\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027351 \u0e1a\u0e08.\u0e04\u0e23\u0e31\u0e27\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2b\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5bbf\u6cca\u30fb\u98f2\u98df 395  \u0e16\u0e19\u0e19\u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569022219\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e27\u0e2d\u0e25\u0e4c\u0e04 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022219 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e27\u0e2d\u0e25\u0e4c\u0e04 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e41\u0e15\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 147\/97  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e13\u0e35\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e1e\u0e32\u0e23\u0e4c\u0e04 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022308\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e1f\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022308 \u0e1a\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e1f\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e22\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e0a\u0e34\u0e01\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u82b8\u8853\u30fb\u5a2f\u697d 91\/109  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022316\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78300\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78300\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022316 \u0e1a\u0e08.\u0e40\u0e08\u0e1e\u0e35 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e1f\u0e2d\u0e23\u0e4c\u0e0b \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 78300 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e40\u0e07\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 33\/329  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e39\u0e23\u0e34\u0e25\u0e33\u0e25\u0e39\u0e01\u0e01\u0e32\u0e04\u0e25\u0e2d\u0e077 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569022383\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e21\u0e31\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022383 \u0e1a\u0e08.\u0e21\u0e32\u0e22\u0e21\u0e31\u0e21\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21  \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 163\/16  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569037983\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58201\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58201\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037983 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e41\u0e2d\u0e25\u0e41\u0e2d\u0e25 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 58201 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e40\u0e01\u0e21 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e01\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 171\/149  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0435569001146\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\",\"search_text\":\"0435569001146 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e20\u0e34\u0e0d\u0e42\u0e0d\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c  \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u30ce\u30fc\u30f3\u30ab\u30fc\u30a4\u770c\"},{\"reg_no\":\"0503569005050\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e31\u0e13\u0e27\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b 9889\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005050 \u0e2b\u0e08.\u0e2d\u0e31\u0e13\u0e27\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b 9889 2569-07-20 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19  \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e32\u0e07\u0e2f \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07\u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 263\/27  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0703569000498\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c 2536\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45403\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45403\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0703569000498 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c 2536 2569-07-20 100000 45403 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e48\u0e2d\u0e44\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 99\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0705569003294\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e23\u0e4c\u0e22\u0e39 168 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0705569003294 \u0e1a\u0e08.\u0e41\u0e04\u0e23\u0e4c\u0e22\u0e39 168 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e37\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e32\u0e0a\u0e1a\u0e38\u0e23\u0e35 \u30e9\u30fc\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002166\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e14\u0e43\u0e2a\u0e2a\u0e38\u0e02\u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002166 \u0e1a\u0e08.\u0e2a\u0e14\u0e43\u0e2a\u0e2a\u0e38\u0e02\u0e2a\u0e15\u0e32\u0e07\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e2a\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e1e\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e25\u0e15\u0e34\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e32\u0e07\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e22\u0e39\u0e17\u0e39\u0e1b  \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 727  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0813569000471\",\"name_th\":\"\u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"95110\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"95110\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0813569000471 \u0e2b\u0e08.\u0e01\u0e23\u0e35\u0e19 \u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-20 100000 95110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 152  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569013337\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013337 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e21 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 69200 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e20\u0e32\u0e29\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e0f\u0e2b\u0e21\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 130\/73  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0845569010591\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e42\u0e2d\u0e23\u0e48\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010591 \u0e1a\u0e08.\u0e2a\u0e22\u0e32\u0e21\u0e42\u0e2d\u0e23\u0e48\u0e32 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 100000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 137\/58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0815569002165\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-19\",\"reg_date_sort\":25690719,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002165 \u0e1a\u0e08.\u0e1b\u0e31\u0e0d\u0e13\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-19 100000 58202 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e27\u0e23\u0e4c \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 81\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0105569135765\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135765 \u0e1a\u0e08.\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e04\u0e25\u0e31\u0e1a \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299\/698  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135773\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d \u0e1a\u0e34\u0e2a\u0e2a\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135773 \u0e1a\u0e08.\u0e08\u0e35\u0e40\u0e2d \u0e1a\u0e34\u0e2a\u0e2a\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/32  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023835\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e19\u0e32\u0e27\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55109\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55109\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023835 \u0e1a\u0e08.\u0e40\u0e17\u0e1e\u0e19\u0e32\u0e27\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 55109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e48\u0e32\u0e22\u0e25\u0e39\u0e01\u0e40\u0e2a\u0e37\u0e2d \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 90  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0333569000696\",\"name_th\":\"\u0e2b\u0e08.\u0e18\u0e34\u0e15\u0e32 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 1999\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000696 \u0e2b\u0e08.\u0e18\u0e34\u0e15\u0e32 \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 1999 2569-07-18 100000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0345569003280\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e2d\u0e1e\u0e38\u0e12 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0345569003280 \u0e1a\u0e08.\u0e01\u0e2d\u0e1e\u0e38\u0e12 \u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e19\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e42\u0e0b\u0e40\u0e0b\u0e35\u0e22\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1b\u0e44\u0e0b\u0e15\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34 \u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e1e \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e0b\u0e35\u0e23\u0e35\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e0b\u0e35\u0e48\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e42\u0e06\u0e29\u0e13\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0413569001641\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e31\u0e07\u0e17\u0e2d\u0e07\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47215\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47215\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001641 \u0e2b\u0e08.\u0e1b\u0e31\u0e07\u0e17\u0e2d\u0e07\u0e17\u0e27\u0e35\u0e04\u0e39\u0e13 2569-07-18 100000 47215 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 330\/60   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 330\/60 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e2d\u0e22\u0e27\u0e34\u0e25\u0e25\u0e48\u0e322 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 2 \u0e16\u0e19\u0e19\u0e2d\u0e38\u0e14\u0e23\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0505569016207\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e23. \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016207 \u0e1a\u0e08.\u0e14\u0e23. \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 77\/31  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48-\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016215\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e17\u0e19 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016215 \u0e1a\u0e08.\u0e04\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a\u0e42\u0e17\u0e19 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 298\/32  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569016258\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e33\u0e14\u0e35 \u0e2a\u0e40\u0e1b\u0e0b \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 2569 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016258 \u0e1a\u0e08.\u0e23\u0e33\u0e14\u0e35 \u0e2a\u0e40\u0e1b\u0e0b \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c 2569 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e07\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e27\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 129\/42  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0515569001447\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e35\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0515569001447 \u0e1a\u0e08.\u0e14\u0e35\u0e1a\u0e35\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0605569002141\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e33\u0e40\u0e25\u0e14\u0e35 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002141 \u0e1a\u0e08.\u0e17\u0e33\u0e40\u0e25\u0e14\u0e35 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 358\/28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0735569007290\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46521\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46521\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569007290 \u0e1a\u0e08.\u0e1f\u0e34\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 46521 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e1c\u0e07\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e31\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e17\u0e48\u0e2d\u0e23\u0e49\u0e2d\u0e22\u0e2a\u0e32\u0e22\u0e44\u0e1f \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c\u0e15\u0e48\u0e32\u0e07 \u0e46  \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0835569013299\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46699\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46699\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013299 \u0e1a\u0e08.\u0e44\u0e17\u0e22\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e21\u0e34\u0e23\u0e4c\u0e0b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 46699 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013311\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e19\u0e1e\u0e49\u0e2d\u0e22\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-18\",\"reg_date_sort\":25690718,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013311 \u0e1a\u0e08.\u0e40\u0e21\u0e19\u0e1e\u0e49\u0e2d\u0e22\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-18 100000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1b\u0e23\u0e38\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e02\u0e49\u0e32\u0e27\u0e41\u0e01\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19 \u88fd\u9020 88\/38  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569007625\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e0b\u0e3569 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007625 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e0b\u0e3569 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c 2569-07-17 100000 52292 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 111  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e25\u0e2d\u0e22\u0e1f\u0e49\u0e32\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e0b\u0e2d\u0e22 25 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0103569007676\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007676 \u0e2b\u0e08.\u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49\u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e1a\u0e35\u0e40\u0e04\u0e40\u0e04 2569-07-17 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 32  \u0e0b\u0e2d\u0e22 \u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c 43 \u0e41\u0e22\u0e01 18 \u0e16\u0e19\u0e19\u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134980\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e01\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47911\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47911\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134980 \u0e1a\u0e08.\u0e01\u0e39\u0e4a\u0e14\u0e01\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 47911 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e2a\u0e30\u0e2a\u0e21 \u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e07\u0e32\u0e19\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e49\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1044\/8  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e23\u0e35\u0e40\u0e1e\u0e0a\u0e23 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135099\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2e\u0e42\u0e23\u0e42\u0e0b\u0e25\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96304\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96304\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135099 \u0e1a\u0e08.\u0e42\u0e2e\u0e42\u0e23\u0e42\u0e0b\u0e25\u0e41\u0e25\u0e47\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 96304 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e1e\u0e22\u0e32\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e42\u0e2b\u0e23\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 370  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 67 \u0e41\u0e22\u0e01 6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135251\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e21\u0e40\u0e21\u0e19\u0e17\u0e4c\u0e15\u0e31\u0e21 2 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135251 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e42\u0e21\u0e40\u0e21\u0e19\u0e17\u0e4c\u0e15\u0e31\u0e21 2 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e25\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22  \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 446  \u0e0b\u0e2d\u0e22 \u0e40\u0e04\u0e2b\u0e30\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 64 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569135561\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85493\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85493\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135561 \u0e1a\u0e08.\u0e1e\u0e25\u0e2d\u0e22\u0e40\u0e25\u0e34\u0e23\u0e4c\u0e19 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 85493 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e17\u0e1a\u0e17\u0e27\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e1d\u0e36\u0e01\u0e2b\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19  \u0e15\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e01\u0e27\u0e14\u0e27\u0e34\u0e0a\u0e32 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e0b\u0e15\u0e4c (on-site) \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c  (online) \u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19 \u6559\u80b2 44\/342  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 147 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026982\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e27\u0e2d\u0e23\u0e34\u0e17\u0e31\u0e2a \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026982 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e40\u0e27\u0e2d\u0e23\u0e34\u0e17\u0e31\u0e2a \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e31\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e07\u0e34\u0e19\u0e19\u0e31\u0e49\u0e19 \u4e0d\u52d5\u7523 161\/148  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e31\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c\u0e2a \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19-\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026991\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026991 \u0e1a\u0e08.\u0e1e\u0e32\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u60c5\u5831\u901a\u4fe1\u30fbit 51  \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e19\u0e19\u0e17\u0e4c 1 \u0e41\u0e22\u0e01 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569027016\",\"name_th\":\"\u0e1a\u0e08.\u0e09\u0e31\u0e15\u0e23\u0e18\u0e19\u0e32\u0e42\u0e0a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027016 \u0e1a\u0e08.\u0e09\u0e31\u0e15\u0e23\u0e18\u0e19\u0e32\u0e42\u0e0a\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 42909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e27\u0e34\u0e08\u0e34\u0e15\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e33\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5efa\u8a2d 69\/58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021972\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e44\u0e0a\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021972 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a.\u0e44\u0e0a\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e23\u0e4c\u0e40\u0e0b\u0e25\u0e25\u0e4c) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 86\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0303569002770\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002770 \u0e2b\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e41\u0e2d\u0e25\u0e1e\u0e35 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-17 100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e01\u0e49\u0e44\u0e02\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 923  \u0e16\u0e19\u0e19\u0e40\u0e14\u0e0a\u0e2d\u0e38\u0e14\u0e21 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0415569003726\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e20\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15 \u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11041\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11041\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003726 \u0e1a\u0e08.\u0e2a\u0e38\u0e20\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15 \u0e40\u0e1e\u0e35\u0e22\u0e27 \u0e27\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 11041 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u88fd\u9020 54  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0415569003734\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e41\u0e17\u0e04\u0e15\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003734 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e1f\u0e48\u0e32 \u0e41\u0e17\u0e04\u0e15\u0e34\u0e04\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e14\u0e34\u0e19\u0e1b\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0503569005009\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569005009 \u0e2b\u0e08.\u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e01\u0e32\u0e23\u0e4c\u0e14 \u0e40\u0e2d\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e1e\u0e23\u0e2a\u0e4c 2569-07-17 100000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 231\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0655569002311\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e15 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002311 \u0e1a\u0e08.\u0e17\u0e23\u0e34\u0e19\u0e34\u0e15\u0e35\u0e49 \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e15 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 222\/24  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0745569007583\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e04\u0e39\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007583 \u0e1a\u0e08.\u0e27\u0e34\u0e19\u0e04\u0e39\u0e25\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 100000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e1c\u0e07\u0e27\u0e07\u0e08\u0e23\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e04\u0e04\u0e32\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e27\u0e34\u0e0a\u0e31\u0e19\u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e0b\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e23\u0e27\u0e08\u0e08\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13 \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e43\u0e19\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e43\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 36\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0813569000462\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e40\u0e04\u0e17\u0e35 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46108\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46108\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0813569000462 \u0e2b\u0e08.\u0e27\u0e35\u0e40\u0e04\u0e17\u0e35 \u0e25\u0e35\u0e14\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b 2569-07-17 100000 46108 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 51  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0105569134149\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2a \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134149 \u0e1a\u0e08.\u0e40\u0e2d\u0e0a\u0e41\u0e2d\u0e25\u0e40\u0e2d\u0e2a \u0e1a\u0e23\u0e34\u0e14\u0e08\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e4d\u0e32\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e4d\u0e32\u0e41\u0e19\u0e30\u0e19\u0e4d\u0e32 \u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 555  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e2a\u0e32 \u0e27\u0e31\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e2d \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 2 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134173\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e41\u0e01\u0e19\u0e2a\u0e40\u0e1b\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134173 \u0e1a\u0e08.\u0e2a\u0e41\u0e01\u0e19\u0e2a\u0e40\u0e1b\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 71201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e01\u0e48\u0e2d\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 3\/50  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e04\u0e34\u0e17\u0e17\u0e4c \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 163 \u0e16\u0e19\u0e19\u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134262\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e19\u0e34\u0e42\u0e04 \u0e40\u0e1e\u0e47\u0e15\u0e42\u0e15\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134262 \u0e1a\u0e08.\u0e2d\u0e32\u0e19\u0e34\u0e42\u0e04 \u0e40\u0e1e\u0e47\u0e15\u0e42\u0e15\u0e30 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10\/100  \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134297\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e48\u0e2d\u0e28\u0e23\u0e35 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134297 \u0e1a\u0e08.\u0e2b\u0e25\u0e48\u0e2d\u0e28\u0e23\u0e35 \u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 203\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e44\u0e21\u0e15\u0e23\u0e35\u0e08\u0e34\u0e15\u0e15\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134670\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e34\u0e0b \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134670 \u0e1a\u0e08.\u0e42\u0e01\u0e25\u0e1a\u0e34\u0e0b \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 70103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 39\/34  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e32\u0e07\u0e19\u0e32\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 25 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134793\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e42\u0e27\u0e17 \u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134793 \u0e1a\u0e08.\u0e14\u0e35\u0e42\u0e27\u0e17 \u0e2d\u0e34\u0e19\u0e1f\u0e23\u0e32\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e49\u0e32\u0e22\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u5efa\u8a2d 255  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2793 (\u0e42\u0e0a\u0e04\u0e0a\u0e31\u0e223) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134823\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e2a\u0e4c \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134823 \u0e1a\u0e08.\u0e0b\u0e35\u0e2a\u0e4c \u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 (point of sales : pos) \u60c5\u5831\u901a\u4fe1\u30fbit 99\/262  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e2a\u0e34\u0e23\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 15 (\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134840\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134840 \u0e1a\u0e08.\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u82b8\u8853\u30fb\u5a2f\u697d 99\/262  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e2a\u0e34\u0e23\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 \u0e0b\u0e2d\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e35\u0e11\u0e32 15 (\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e23\u0e48\u0e27\u0e21\u0e43\u0e08) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134874\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134874 \u0e1a\u0e08.\u0e1e\u0e35\u0e22\u0e39 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/32  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134882\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46104\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46104\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134882 \u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e35 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 46104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e04\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e04\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 20\/32  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e1e\u0e31\u0e12\u0e19\u0e32 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023509\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e39\u0e4a\u0e14\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023509 \u0e1a\u0e08.\u0e14\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e39\u0e4a\u0e14\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 46109 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 888\/131  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026737\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e25\u0e2d\u0e23\u0e34\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63120\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63120\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026737 \u0e1a\u0e08.\u0e1f\u0e25\u0e2d\u0e23\u0e34\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 63120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e1a\u0e04\u0e39\u0e48\u0e04\u0e23\u0e39\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30 \u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e27\u0e14\u0e27\u0e34\u0e0a\u0e32 \u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u60c5\u5831\u901a\u4fe1\u30fbit 178\/252  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026966\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e39\u0e01\u0e2e\u0e31\u0e01\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026966 \u0e1a\u0e08.\u0e2e\u0e39\u0e01\u0e2e\u0e31\u0e01\u0e41\u0e1f\u0e21\u0e34\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 63112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e15\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e23\u0e35\u0e27\u0e34\u0e27 \u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e01\u0e21\u0e2a\u0e4c \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23 \u0e07\u0e32\u0e19\u0e1e\u0e32\u0e01\u0e29\u0e4c\u0e40\u0e2a\u0e35\u0e22\u0e07  \u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07 \u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e4c\u0e40\u0e01\u0e21\u0e2a\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 100\/162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026974\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e44\u0e18\u0e23\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026974 \u0e1a\u0e08.\u0e40\u0e04\u0e17\u0e35 \u0e44\u0e18\u0e23\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e4d\u0e32\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 67\/200  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0195569002617\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35\u0e42\u0e1f\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0195569002617 \u0e1a\u0e08.\u0e17\u0e35\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e14\u0e35\u0e42\u0e1f\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 46522 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e15\u0e42\u0e1f\u0e19 \u0e41\u0e17\u0e47\u0e1a\u0e40\u0e25\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 192  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0305569007404\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e14\u0e35\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007404 \u0e1a\u0e08.\u0e2d\u0e23\u0e48\u0e2d\u0e22\u0e14\u0e35\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e15\u0e32\u0e21\u0e2d\u0e2d\u0e40\u0e14\u0e2d\u0e23\u0e4c \u0e02\u0e19\u0e21 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e02\u0e19\u0e21\u0e44\u0e17\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 54\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0343569001935\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e1a\u0e32\u0e14\u0e32\u0e25\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42201\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42201\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0343569001935 \u0e2b\u0e08.\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e0a\u0e31\u0e22 \u0e1a\u0e32\u0e14\u0e32\u0e25 2569-07-16 100000 42201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e08\u0e32\u0e30\u0e19\u0e49\u0e33\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e02\u0e38\u0e14\u0e40\u0e08\u0e32\u0e30\u0e1a\u0e48\u0e2d\u0e19\u0e49\u0e33 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e33\u0e23\u0e27\u0e08\u0e2b\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e19\u0e49\u0e33 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e08\u0e32\u0e30\u0e19\u0e49\u0e33\u0e1a\u0e32\u0e14\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2d\u0e38\u0e1a\u0e25\u0e23\u0e32\u0e0a\u0e18\u0e32\u0e19\u0e35 \u30a6\u30dc\u30f3\u30e9\u30fc\u30c1\u30e3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0403569003201\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2026\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003201 \u0e2b\u0e08.\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2026 2569-07-16 100000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u91d1\u878d\u30fb\u4fdd\u967a 222\/148  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569016126\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e2a \u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016126 \u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e40\u0e2d\u0e2a \u0e2a\u0e40\u0e1f\u0e35\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 88\/363  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000741\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e34\u0e0a\u0e0a\u0e35\u0e48 \u0e23\u0e27\u0e22 \u0e23\u0e27\u0e22\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000741 \u0e2b\u0e08.\u0e23\u0e34\u0e0a\u0e0a\u0e35\u0e48 \u0e23\u0e27\u0e22 \u0e23\u0e27\u0e22 2569-07-16 100000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 112  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0643569000502\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46522\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46522\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22\",\"province_ja\":\"\u30b9\u30b3\u30fc\u30bf\u30a4\u770c\",\"search_text\":\"0643569000502 \u0e2b\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c 2569-07-16 100000 46522 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e02\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e1a\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 (resellre) \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e4a\u0e15 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 197\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e42\u0e02\u0e17\u0e31\u0e22 \u30b9\u30b3\u30fc\u30bf\u30a4\u770c\"},{\"reg_no\":\"0815569002114\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e34\u0e20\u0e39 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002114 \u0e1a\u0e08.\u0e20\u0e34\u0e20\u0e39 \u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e41\u0e25\u0e30\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0835569013213\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013213 \u0e1a\u0e08.\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 77101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e02\u0e31\u0e1a\u0e23\u0e16 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 88\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e40\u0e0a\u0e34\u0e07\u0e17\u0e30\u0e40\u0e25 14 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e2a\u0e38\u0e19\u0e17\u0e23 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0835569013221\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e39\u0e1f\u0e27\u0e34\u0e17\u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86909\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86909\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013221 \u0e1a\u0e08.\u0e21\u0e39\u0e1f\u0e27\u0e34\u0e17\u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 100000 86909 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e42\u0e22\u0e04\u0e30 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u533b\u7642\u30fb\u798f\u7949 7   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 36 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e40\u0e01\u0e32\u0e30\u0e41\u0e01\u0e49\u0e27 16 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e01\u0e23\u0e30\u0e29\u0e31\u0e15\u0e23\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569007544\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e2a\u0e32\u0e1e\u0e32\u0e23\u0e27\u0e22\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46411\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46411\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007544 \u0e2b\u0e08.\u0e23\u0e2a\u0e32\u0e1e\u0e32\u0e23\u0e27\u0e22 2569-07-15 100000 46411 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4020  \u0e0b\u0e2d\u0e22 \u0e04\u0e07\u0e2d\u0e48\u0e33 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133410\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e2a\u0e32\u0e21\u0e1e\u0e23\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133410 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e2a\u0e32\u0e21\u0e1e\u0e23\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e0b\u0e2d\u0e22 \u0e21\u0e13\u0e11\u0e25\u0e17\u0e2d\u0e07 \u0e16\u0e19\u0e19\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25\u0e2a\u0e32\u0e222 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133495\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46318\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46318\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133495 \u0e1a\u0e08.\u0e40\u0e21\u0e0b\u0e31\u0e19 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 46318 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e40\u0e21\u0e25\u0e47\u0e14\u0e01\u0e32\u0e41\u0e1f \u0e43\u0e1a\u0e0a\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 98\/59  \u0e0b\u0e2d\u0e22 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01005 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133525\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e39\u0e15\u0e34\u0e01 \u0e40\u0e2d\u0e1a\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133525 \u0e1a\u0e08.\u0e25\u0e32\u0e1a\u0e39\u0e15\u0e34\u0e01 \u0e40\u0e2d\u0e1a\u0e35\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2b\u0e2d\u0e1e\u0e31\u0e01 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e15\u0e40\u0e21\u0e19\u0e15\u0e4c \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e0a\u0e48\u0e32 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e38\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 235\/6  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 21 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 21 (\u0e2d\u0e42\u0e28\u0e01) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133592\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e01\u0e34\u0e42\u0e21 \u0e40\u0e1e\u0e47\u0e17 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46206\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46206\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133592 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e01\u0e34\u0e42\u0e21 \u0e40\u0e1e\u0e47\u0e17 \u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 46206 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e31\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e19\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e22\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9\/30  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e34\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a46 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133894\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e21\u0e34\u0e42\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133894 \u0e1a\u0e08.\u0e0b\u0e32\u0e21\u0e34\u0e42\u0e19 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e02\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0b\u0e34\u0e01\u0e32\u0e23\u0e4c\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e40\u0e17\u0e48\u0e32\u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/2  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e3523 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 23 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569134009\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e22\u0e01\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93112\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93112\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569134009 \u0e1a\u0e08.\u0e42\u0e22\u0e01\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 93112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u82b8\u8853\u30fb\u5a2f\u697d 8\/25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e18\u0e23\u0e23\u0e21 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e17\u0e23\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023461\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e2b\u0e19\u0e39\u0e2a\u0e35\u0e48\u0e02\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96302\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96302\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023461 \u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e2b\u0e19\u0e39\u0e2a\u0e35\u0e48\u0e02\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 96302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e19\u0e31\u0e02\u0e41\u0e25\u0e30\u0e41\u0e21\u0e27\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 59\/395  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026648\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e07\u0e40\u0e08\u0e34\u0e25\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026648 \u0e1a\u0e08.\u0e41\u0e2d\u0e07\u0e40\u0e08\u0e34\u0e25\u0e40\u0e21\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e08\u0e32\u0e01\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e43\u0e2b\u0e21\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e43\u0e0a\u0e49 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e23\u0e35\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2d\u0e31\u0e1b\u0e44\u0e0b\u0e40\u0e04\u0e34\u0e25 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u88fd\u9020 109\/66  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e32\u0e22\u0e40\u0e1e\u0e25\u0e2a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c-\u0e1b\u0e32\u0e01\u0e40\u0e01\u0e23\u0e47\u0e1456 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c-\u0e1b\u0e32\u0e01\u0e40\u0e01\u0e23\u0e47\u0e14 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026656\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e21\u0e49\u0e1e\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026656 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e21\u0e49\u0e1e\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 77210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e23\u0e37\u0e2d\u0e04\u0e32\u0e22\u0e31\u0e04 \u0e01\u0e23\u0e30\u0e14\u0e32\u0e19\u0e22\u0e37\u0e19\u0e1e\u0e32\u0e22 \u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e19\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 119\/395  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e14\u0e40\u0e1f\u0e04\u0e40\u0e1e\u0e25\u0e2a \u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c 2 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026681\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e14\u0e21\u0e34\u0e41\u0e19\u0e19\u0e17\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026681 \u0e1a\u0e08.\u0e42\u0e14\u0e21\u0e34\u0e41\u0e19\u0e19\u0e17\u0e4c \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e01\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 164\/520  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e14\u0e34\u0e40\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e31\u0e25\u0e14\u0e4c\u0e1e\u0e32\u0e23\u0e4c\u0e042 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002470\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e0b\u0e14\u0e40\u0e2d \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"29309\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"29309\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002470 \u0e2b\u0e08.\u0e1a\u0e35\u0e41\u0e0b\u0e14\u0e40\u0e2d \u0e40\u0e23\u0e0b\u0e0b\u0e34\u0e48\u0e07 \u0e1e\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c 2569-07-15 100000 29309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e14\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e23\u0e16\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 269  \u0e0b\u0e2d\u0e22 \u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0133569002488\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002488 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e40\u0e04\u0e40\u0e17\u0e2d\u0e23\u0e34\u0e48\u0e07 2569-07-15 100000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46  \u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e01\u0e33\u0e2b\u0e19\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 493\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0193569000787\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b5\u30e9\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0193569000787 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e0a \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-15 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 211\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e2a\u0e23\u0e30\u0e1a\u0e38\u0e23\u0e35 \u30b5\u30e9\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003841\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e19 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003841 \u0e1a\u0e08.\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e25\u0e34\u0e19 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2a\u0e42\u0e15\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 83\/6  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0403569003155\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e34\u0e27\u0e17\u0e35\u0e27\u0e35\u0e19\u0e34\u0e27\u0e2a\u0e4c\u0e1e\u0e25\u0e31\u0e2a\u0e14\u0e35\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63120\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63120\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569003155 \u0e2b\u0e08.\u0e19\u0e34\u0e27\u0e17\u0e35\u0e27\u0e35\u0e19\u0e34\u0e27\u0e2a\u0e4c\u0e1e\u0e25\u0e31\u0e2a\u0e14\u0e35 2569-07-15 100000 63120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e02\u0e48\u0e32\u0e27\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 940\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 27 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0503569004941\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e0d\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004941 \u0e2b\u0e08.\u0e0a\u0e0d\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-15 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58\/366  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0503569004967\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e48\u0e21\u0e35\u0e48 \u0e23\u0e48\u0e33\u0e23\u0e27\u0e22\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47221\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47221\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004967 \u0e2b\u0e08.\u0e1e\u0e35\u0e48\u0e21\u0e35\u0e48 \u0e23\u0e48\u0e33\u0e23\u0e27\u0e22 2569-07-15 100000 47221 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 223  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 sand box  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 a5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0505569015979\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e21\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c99 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015979 \u0e1a\u0e08.\u0e1a\u0e32\u0e23\u0e21\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c99 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e2a\u0e31\u0e0d\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e44\u0e1b\u0e17\u0e33\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e19\u0e32\u0e22\u0e08\u0e49\u0e32\u0e07 \u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 158\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0513569000716\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000716 \u0e2b\u0e08.\u0e2a\u0e34\u0e23\u0e34\u0e27\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e4a\u0e1b 2026 2569-07-15 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e2b\u0e49\u0e32\u0e07\u0e2f \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 19\/62  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0655569002299\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002299 \u0e1a\u0e08.\u0e15\u0e30\u0e27\u0e31\u0e19\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c (solar cell) \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e23\u0e39\u0e1f\u0e17\u0e47\u0e2d\u0e1b \u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e0b\u0e25\u0e32\u0e23\u0e4c\u0e1f\u0e32\u0e23\u0e4c\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5efa\u8a2d 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0743569001010\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e21\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"22299\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"22299\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0743569001010 \u0e2b\u0e08.\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e21\u0e35\u0e40\u0e08\u0e23\u0e34\u0e0d 2569-07-15 100000 22299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e32\u0e2a\u0e15\u0e34\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 99\/871  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e21\u0e32\u0e18\u0e34\u0e42\u0e2d \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0845569010397\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e32\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010397 \u0e1a\u0e08.\u0e40\u0e17\u0e2d\u0e23\u0e32\u0e42\u0e19\u0e27\u0e48\u0e32 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 100000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569133169\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e1e\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68101\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68101\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133169 \u0e1a\u0e08.\u0e2d\u0e35\u0e1e\u0e35 \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e41\u0e04\u0e1b\u0e1b\u0e34\u0e15\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 68101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e32\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u4e0d\u52d5\u7523 2248\/26   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 26 \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133231\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e39\u0e40\u0e08\u0e49\u0e40\u0e08\u0e47\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46311\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46311\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133231 \u0e1a\u0e08.\u0e23\u0e49\u0e32\u0e19\u0e2b\u0e21\u0e39\u0e40\u0e08\u0e49\u0e40\u0e08\u0e47\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 46311 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e01\u0e23 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e38\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e2a\u0e38\u0e01\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 22\/7  \u0e0b\u0e2d\u0e22 \u0e2a\u0e21\u0e1b\u0e23\u0e32\u0e23\u0e16\u0e19\u0e32 \u0e41\u0e22\u0e01 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133258\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e21\u0e32\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133258 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e21\u0e32\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 77302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e37\u0e2d\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 942\/43  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e0a\u0e32\u0e0d\u0e2d\u0e34\u0e2a\u0e2a\u0e23\u0e30\u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e48 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569133282\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e1a\u0e32\u0e22 \u0e40\u0e19\u0e2a\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569133282 \u0e1a\u0e08.\u0e2a\u0e1a\u0e32\u0e22 \u0e40\u0e19\u0e2a\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 115\/4-115\/5  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026460\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e35\u0e48\u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026460 \u0e1a\u0e08.\u0e21\u0e32\u0e19\u0e35\u0e48\u0e21\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 70201 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e35\u0e2c\u0e32 \u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/335  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e4c\u0e25\u0e14\u0e32\u0e1a\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e23\u0e31\u0e01\u0e43\u0e2b\u0e0d\u0e48-\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021557\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e17\u0e40\u0e17\u0e34\u0e25 \u0e27\u0e39\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021557 \u0e1a\u0e08.\u0e25\u0e34\u0e17\u0e40\u0e17\u0e34\u0e25 \u0e27\u0e39\u0e1f\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 133\/453  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0303569002711\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e2d\u0e27\u0e4c\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85499\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85499\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002711 \u0e2b\u0e08.\u0e1e\u0e35\u0e40\u0e04 \u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e2d\u0e27\u0e4c 2569-07-14 100000 85499 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1b\u0e10\u0e21\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e31\u0e49\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u6559\u80b2 20\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e1e\u0e22\u0e2d\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0565569000637\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e23\u0e31\u0e01\u0e08\u0e31\u0e01\u0e23\u0e27\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32\",\"province_ja\":\"\u30d1\u30e4\u30aa\u770c\",\"search_text\":\"0565569000637 \u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e23\u0e31\u0e01\u0e08\u0e31\u0e01\u0e23\u0e27\u0e32\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 73102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e17\u0e38\u0e01\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (social media influencer\/creator) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 112\/31  \u0e16\u0e19\u0e19\u0e1f\u0e32\u0e01\u0e19\u0e49\u0e33 \u0e08.\u0e1e\u0e30\u0e40\u0e22\u0e32 \u30d1\u30e4\u30aa\u770c\"},{\"reg_no\":\"0835569012977\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e17\u0e23\u0e34\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68103\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68103\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012977 \u0e1a\u0e08.\u0e2d\u0e31\u0e19\u0e14\u0e32\u0e17\u0e23\u0e34\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 68103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e0d\u52d5\u7523 65\/377  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0915569000340\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e15\u0e39\u0e25\",\"province_ja\":\"\u30b5\u30c8\u30a5\u30fc\u30f3\u770c\",\"search_text\":\"0915569000340 \u0e1a\u0e08.\u0e41\u0e2d\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 80  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e15\u0e39\u0e25 \u30b5\u30c8\u30a5\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569132227\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132227 \u0e1a\u0e08.\u0e27\u0e31\u0e19 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e0b\u0e34\u0e2a\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 100000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14 \u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 193  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e31\u0e19 \u0e41\u0e1a\u0e07\u0e04\u0e47\u0e2d\u0e01 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c 5 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132618\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e23\u0e34\u0e0a\u0e01\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132618 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30\u0e23\u0e34\u0e0a\u0e01\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 100000 82302 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 88\/214  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e25\u0e35\u0e42\u0e19\u0e48 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 76 \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 76 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569132642\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e2a\u0e21\u0e32\u0e22\u0e14\u0e4c \u0e42\u0e27\u0e22\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79110\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79110\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132642 \u0e1a\u0e08.\u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e2a\u0e21\u0e32\u0e22\u0e14\u0e4c \u0e42\u0e27\u0e22\u0e32\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 100000 79110 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e19\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d \u0e23\u0e31\u0e1a\u0e08\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e25\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e2a\u0e33\u0e23\u0e32\u0e0d \u0e40\u0e23\u0e37\u0e2d\u0e14\u0e34\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c \u0e40\u0e23\u0e37\u0e2d\u0e2b\u0e32\u0e07\u0e22\u0e32\u0e27 \u0e40\u0e23\u0e37\u0e2d\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 1\/4  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c 8 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569003025\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e23\u0e13\u0e34\u0e20\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569003025 \u0e2b\u0e08.\u0e1e\u0e23\u0e13\u0e34\u0e20\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e34\u0e08 2569-07-13 100000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 126\/170  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569037029\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e40\u0e21\u0e17\u0e31\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037029 \u0e1a\u0e08.\u0e17\u0e47\u0e2d\u0e1b\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e23\u0e32 \u0e40\u0e21\u0e17\u0e31\u0e25\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 100000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32\u0e42\u0e25\u0e2b\u0e30 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 190\/302  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0725569002093\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47214\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47214\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0725569002093 \u0e1a\u0e08.\u0e41\u0e2e\u0e1b\u0e1b\u0e35\u0e49\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 100000 47214 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 114  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0903569001620\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e40\u0e1b\u0e0b\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47742\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47742\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0903569001620 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e2a\u0e40\u0e1b\u0e0b 2569-07-13 100000 47742 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22  \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e21\u0e37\u0e2d\u0e2a\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569131964\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e35\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131964 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21 \u0e17\u0e35\u0e08\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-12 100000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0a\u0e32 \u0e01\u0e32\u0e41\u0e1f \u0e42\u0e01\u0e42\u0e01\u0e49 \u0e0a\u0e32\u0e40\u0e0a\u0e35\u0e22\u0e27 \u0e04\u0e23\u0e35\u0e21\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e19\u0e21\u0e02\u0e49\u0e19\u0e2b\u0e27\u0e32\u0e19  \u0e19\u0e21\u0e2a\u0e14 \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e17\u0e23\u0e32\u0e22 \u0e2a\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e17 (e-commerce) \u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 50\/1  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e23.9 \u0e0b\u0e2d\u0e22 9 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e23.9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0623569000723\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e2b\u0e34\u0e17\u0e18\u0e34\u0e01\u0e31\u0e25\u0e1b\u0e4c\u0e01\u0e34\u0e08\",\"reg_date\":\"2569-07-12\",\"reg_date_sort\":25690712,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000723 \u0e2b\u0e08.\u0e21\u0e2b\u0e34\u0e17\u0e18\u0e34\u0e01\u0e31\u0e25\u0e1b\u0e4c\u0e01\u0e34\u0e08 2569-07-12 100000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569007374\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e40\u0e21\u0e42\u0e01\u0e30 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007374 \u0e2b\u0e08.\u0e2d\u0e40\u0e21\u0e42\u0e01\u0e30 \u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 2569-07-11 100000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1299\/38  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 the estate srinakarin 2 \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 46 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 77 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131751\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35 \u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131751 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e1a\u0e35 \u0e23\u0e27\u0e22\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 100000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e38\u0e4b\u0e22 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14-\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 105\/17  \u0e16\u0e19\u0e19\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131760\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58202\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58202\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131760 \u0e1a\u0e08.\u0e21\u0e31\u0e48\u0e07\u0e25\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 100000 58202 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (enterprise resource planning ? erp)           \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c (saas) \u60c5\u5831\u901a\u4fe1\u30fbit 114\/44  \u0e16\u0e19\u0e19\u0e44\u0e17\u0e22\u0e23\u0e32\u0e21\u0e31\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131786\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131786 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19.\u0e1e\u0e35.\u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 100000 64202 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u91d1\u878d\u30fb\u4fdd\u967a 14  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0a\u0e19\u0e1a\u0e17 3 \u0e41\u0e22\u0e01 7 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131891\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e1b\u0e40\u0e08\u0e04 \u0e2d\u0e2d\u0e1f \u0e41\u0e04\u0e23\u0e4c \u0e42\u0e2d\u0e42\u0e2d\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131891 \u0e1a\u0e08.\u0e2d\u0e2d\u0e1b\u0e40\u0e08\u0e04 \u0e2d\u0e2d\u0e1f \u0e41\u0e04\u0e23\u0e4c \u0e42\u0e2d\u0e42\u0e2d\u0e0b\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 100000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 11\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e32\u0e23\u0e32\u0e2a\u0e34\u0e23\u0e34 \u0e2a\u0e32\u0e17\u0e23-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569026184\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e01\u0e49\u0e32 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026184 \u0e1a\u0e08.\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e01\u0e49\u0e32 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (e-marketplace) \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e04\u0e48\u0e32\u0e18\u0e23\u0e23\u0e21\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e04\u0e48\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 198\/86  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e44\u0e1e\u0e23\u0e4c\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e01\u0e23\u0e27\u0e22-\u0e44\u0e17\u0e23\u0e19\u0e49\u0e2d\u0e22 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002372\",\"name_th\":\"\u0e2b\u0e08.\u0e1e\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39.\u0e1e\u0e23\u0e35\u0e0a\u0e34\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25999\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25999\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002372 \u0e2b\u0e08.\u0e1e\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e49\u0e25\u0e22\u0e39.\u0e1e\u0e23\u0e35\u0e0a\u0e34\u0e0a\u0e31\u0e48\u0e19 2569-07-11 100000 25999 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e39\u0e1b \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 27\/101  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0575569004471\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45101\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45101\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0575569004471 \u0e1a\u0e08.\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 100000 45101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 21 \u0e0b\u0e2d\u0e22 2 \u0e16\u0e19\u0e19\u0e2a\u0e34\u0e07\u0e2b\u0e44\u0e04\u0e25 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0605569002001\",\"name_th\":\"\u0e1a\u0e08.\u0e13 \u0e04\u0e2d\u0e19\u0e2a\u0e30\u0e2b\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569002001 \u0e1a\u0e08.\u0e13 \u0e04\u0e2d\u0e19\u0e2a\u0e30\u0e2b\u0e27\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 100000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e04\u0e2d\u0e21\u0e21\u0e39\u0e19\u0e34\u0e15\u0e35\u0e49\u0e21\u0e2d\u0e25\u0e25\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14 \u5efa\u8a2d 58  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0723569000650\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e31\u0e19\u0e17\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u0e01\u0e38\u0e25\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47211\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47211\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0723569000650 \u0e2b\u0e08.\u0e19\u0e31\u0e19\u0e17\u0e40\u0e28\u0e23\u0e29\u0e10\u0e32\u0e01\u0e38\u0e25 2569-07-11 100000 47211 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e0a\u0e48\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e44\u0e01\u0e48 \u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39  \u0e17\u0e31\u0e49\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2a\u0e14 \u0e41\u0e0a\u0e48\u0e40\u0e22\u0e47\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e44\u0e14\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2a\u0e38\u0e1e\u0e23\u0e23\u0e13\u0e1a\u0e38\u0e23\u0e35 \u30b9\u30d1\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0733569001010\",\"name_th\":\"\u0e2b\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569001010 \u0e2b\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-11 100000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \u0e02\u0e19\u0e22\u0e49\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 297\/583  \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0105569131026\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131026 \u0e1a\u0e08.\u0e1a\u0e35\u0e1e\u0e35 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1a\u0e23\u0e23\u0e08\u0e38 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e1e\u0e37\u0e0a \u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 85\/20  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e44\u0e2d\u0e14\u0e35\u0e25 24 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 26 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 24 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131328\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e19\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131328 \u0e1a\u0e08.\u0e40\u0e21\u0e19\u0e39 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c (branding) \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 66\/534  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 79 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131727\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70202\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70202\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131727 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e40\u0e0b\u0e2d\u0e23\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 70202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e07\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19  \u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e01\u0e23\u0e30\u0e41\u0e2a\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19 corporate finance \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 49  \u0e0b\u0e2d\u0e22 \u0e2a\u0e32\u0e22\u0e2a\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022995\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46639\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46639\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022995 \u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e14\u0e35 \u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 46639 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e02\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 345\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569026028\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e2d\u0e35\u0e04\u0e25\u0e34\u0e1b\u0e2a\u0e4c \u0e40\u0e2d\u0e17 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78101\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78101\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026028 \u0e1a\u0e08.\u0e2d\u0e2d\u0e21\u0e19\u0e34 \u0e2d\u0e35\u0e04\u0e25\u0e34\u0e1b\u0e2a\u0e4c \u0e40\u0e2d\u0e17 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 78101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e14\u0e32\u0e23\u0e32 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e19\u0e32\u0e07\u0e41\u0e1a\u0e1a \u0e19\u0e32\u0e22\u0e41\u0e1a\u0e1a \u0e19\u0e31\u0e01\u0e23\u0e35\u0e27\u0e34\u0e27 (influencer) \u0e27\u0e35\u0e40\u0e08 (vj) \u0e04\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c (creator) \u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 (live streamer) \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e17\u0e38\u0e01\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 75\/168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026095\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e02\u0e28\u0e32\u0e19\u0e15\u0e4c\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026095 \u0e1a\u0e08.\u0e1e\u0e23\u0e17\u0e34\u0e1e\u0e22\u0e4c \u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e2a\u0e38\u0e02\u0e28\u0e32\u0e19\u0e15\u0e4c\u0e17\u0e2d\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 70209 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569026109\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e0a\u0e32\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569026109 \u0e1a\u0e08.\u0e42\u0e2d\u0e0a\u0e32\u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e44\u0e2d\u0e28\u0e01\u0e23\u0e35\u0e21 \u0e17\u0e31\u0e49\u0e07\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 (delivery) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 34\/37  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569021352\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33121\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33121\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021352 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e08\u0e40\u0e2d\u0e2a \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 33121 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e30\u0e1a\u0e1a\u0e25\u0e33\u0e40\u0e25\u0e35\u0e22\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u88fd\u9020 35\/379  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e20\u0e31\u0e2a\u0e2a\u0e2312 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569021387\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e38\u0e02\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10794\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10794\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021387 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e2a\u0e38\u0e02\u0e27\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 10794 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 59\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e2b\u0e25\u0e27\u0e07\u0e1b\u0e39\u0e48\u0e22\u0e34\u0e49\u0e21 \u0e16\u0e19\u0e19345 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0215569009262\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e4b\u0e2d\u0e21 \u0e40\u0e21\u0e25\u0e42\u0e25\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009262 \u0e1a\u0e08.\u0e2d\u0e4b\u0e2d\u0e21 \u0e40\u0e21\u0e25\u0e42\u0e25\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content)  \u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e42\u0e14\u0e22\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 928  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0245569003728\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e19\u0e2d\u0e21\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003728 \u0e1a\u0e08.\u0e16\u0e19\u0e2d\u0e21\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e15\u0e25\u0e2d\u0e14\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 487\/303  \u0e16\u0e19\u0e19\u0e28\u0e38\u0e20\u0e01\u0e34\u0e08 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0555569000599\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e04\u0e27\u0e32 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28199\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28199\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e48\u0e32\u0e19\",\"province_ja\":\"\u30ca\u30fc\u30f3\u770c\",\"search_text\":\"0555569000599 \u0e1a\u0e08.\u0e1e\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e40\u0e2d\u0e47\u0e21 \u0e2d\u0e04\u0e27\u0e32 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 28199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e19\u0e49\u0e33 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e2a\u0e32\u0e23\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e44\u0e2a\u0e49\u0e01\u0e23\u0e2d\u0e07 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e23\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 427\/2-3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e08.\u0e19\u0e48\u0e32\u0e19 \u30ca\u30fc\u30f3\u770c\"},{\"reg_no\":\"0845569010273\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e0d\u0e32\u0e14\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0845569010273 \u0e1a\u0e08.\u0e0a\u0e0d\u0e32\u0e14\u0e32 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e17 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 100000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 59\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e34\u0e16\u0e35 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569129471\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129471 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 71101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 221  \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e01\u0e23\u0e38\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129510\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e28\u0e34\u0e27\u0e32 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129510 \u0e1a\u0e08.\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e28\u0e34\u0e27\u0e32 \u0e40\u0e23\u0e35\u0e22\u0e25\u0e40\u0e2d\u0e2a\u0e40\u0e15\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 68201 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 290\/94  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22 \u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34 \u0e16\u0e19\u0e19\u0e23\u0e48\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129668\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e19\u0e38\u0e21\u0e32\u0e19\u0e20\u0e31\u0e17\u0e23\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129668 \u0e1a\u0e08.\u0e2b\u0e19\u0e38\u0e21\u0e32\u0e19\u0e20\u0e31\u0e17\u0e23\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 69100 \u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e14\u0e35 \u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35 \u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e04\u0e14\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 380\/365  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c 3 \u0e1a\u0e32\u0e07\u0e19\u0e32 - \u0e2a\u0e27\u0e19\u0e2b\u0e25\u0e27\u0e07 \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129803\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e43\u0e2a\u0e48\u0e43\u0e08 \u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129803 \u0e1a\u0e08.\u0e1e\u0e35\u0e1e\u0e35\u0e43\u0e2a\u0e48\u0e43\u0e08 \u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e31\u0e19\u0e2b\u0e19\u0e32\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e0a\u0e38\u0e14\u0e2a\u0e39\u0e17 \u0e0a\u0e38\u0e14\u0e23\u0e32\u0e15\u0e23\u0e35  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e0a\u0e38\u0e14\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e22\u0e39\u0e19\u0e34\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 5\/328  \u0e0b\u0e2d\u0e22 \u0e08\u0e15\u0e38\u0e42\u0e0a\u0e15\u0e34 12 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129943\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e27\u0e31\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129943 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e27\u0e31\u0e19 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 355  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129978\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e32\u0e04\u0e34\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129978 \u0e1a\u0e08.\u0e42\u0e0b\u0e25\u0e32\u0e04\u0e34\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 70209 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e01. \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e19 \u0e02. \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 454\/177  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2787 \u0e41\u0e22\u0e0128 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130101\",\"name_th\":\"\u0e1a\u0e08. \u0e14\u0e34 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130101 \u0e1a\u0e08. \u0e14\u0e34 \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e32\u0e17\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e25\u0e47\u0e1a\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 990\/222  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d \u0e40\u0e14\u0e2d\u0e30\u0e21\u0e39\u0e1f \u0e1a\u0e32\u0e07\u0e41\u0e04 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569130283\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2a\u0e22\u0e32\u0e21 1595 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68104\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68104\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130283 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2a\u0e22\u0e32\u0e21 1595 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 68104 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d  \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19 \u0e08\u0e31\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e04\u0e2d\u0e19\u0e42\u0e14\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 39\/195  \u0e16\u0e19\u0e19\u0e01\u0e31\u0e25\u0e1b\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022685\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e37\u0e48\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022685 \u0e1a\u0e08.\u0e0a\u0e37\u0e48\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 111\/180  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30 \u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e2b\u0e19\u0e32\u0e21\u0e41\u0e14\u0e07-\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022707\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e40\u0e17\u0e1e\u0e41\u0e2a\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022707 \u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e40\u0e17\u0e1e\u0e41\u0e2a\u0e19\u0e25\u0e49\u0e32\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 111\/206  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 golden town \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022740\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e17\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022740 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e17\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e2a\u0e37\u0e48\u0e2d\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e41\u0e08\u0e49\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 108\/13  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e27\u0e34\u0e25\u0e40\u0e25\u0e08 \u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e01\u0e21.8 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022898\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e34\u0e19 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022898 \u0e1a\u0e08.\u0e27\u0e35\u0e27\u0e34\u0e19 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e23\u0e31\u0e1a\u0e23\u0e35\u0e27\u0e34\u0e27\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e42\u0e1b\u0e23\u0e42\u0e21\u0e15\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e04\u0e23\u0e35\u0e40\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32tiktok shopee lazada facebook \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 109\/18  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025749\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e17\u0e23\u0e32\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025749 \u0e1a\u0e08.\u0e42\u0e27\u0e25\u0e17\u0e23\u0e32\u0e14\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2d\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e1b\u0e23\u0e2a\u0e20\u0e32\u0e1e \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2a\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2a\u0e30\u0e2a\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32 \u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e49\u0e33 \u0e25\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e27\u0e48\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e04\u0e21\u0e35\u0e08\u0e32\u0e01\u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e4a\u0e32\u0e0b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e21\u0e32\u0e13\u0e39\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e19\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 92\/141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025765\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e15\u0e17\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025765 \u0e1a\u0e08.\u0e27\u0e31\u0e15\u0e17\u0e32\u0e23\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2d\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32  \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e41\u0e1b\u0e23\u0e2a\u0e20\u0e32\u0e1e \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2a\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e23\u0e2d\u0e07  \u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e2a\u0e30\u0e2a\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e21\u0e32\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e49\u0e33 \u0e25\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e27\u0e48\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e04\u0e21\u0e35\u0e08\u0e32\u0e01\u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e4a\u0e32\u0e0b  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e21\u0e32\u0e13\u0e39\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e19\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 92\/141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025781\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e1b\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025781 \u0e1a\u0e08.\u0e25\u0e39\u0e1b\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025897\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e34\u0e15 \u0e13 \u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025897 \u0e1a\u0e08.\u0e08\u0e34\u0e15 \u0e13 \u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 70209 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025901\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e32\u0e2d\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025901 \u0e1a\u0e08.\u0e2d\u0e19\u0e32\u0e2d\u0e19\u0e31\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 70209 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 95\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0133569002305\",\"name_th\":\"\u0e2b\u0e08.\u0e44\u0e25\u0e17\u0e4c \u0e41\u0e21\u0e19 \u0e40\u0e1f\u0e23\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002305 \u0e2b\u0e08.\u0e44\u0e25\u0e17\u0e4c \u0e41\u0e21\u0e19 \u0e40\u0e1f\u0e23\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01 2569-07-09 100000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e21\u0e44\u0e1f \u0e17\u0e35\u0e21\u0e01\u0e25\u0e49\u0e2d\u0e07 \u0e17\u0e35\u0e21\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e19\u0e31\u0e07 \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e0b\u0e35\u0e23\u0e35\u0e48\u0e22\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e01\u0e2d\u0e07\u0e16\u0e48\u0e32\u0e22 \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u60c5\u5831\u901a\u4fe1\u30fbit 78\/30  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0205569036146\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e49\u0e2d\u0e19\u0e17\u0e30\u0e40\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90001\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90001\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036146 \u0e1a\u0e08.\u0e01\u0e49\u0e2d\u0e19\u0e17\u0e30\u0e40\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 90001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19 \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e19\u0e31\u0e01\u0e23\u0e49\u0e2d\u0e07 \u0e1e\u0e34\u0e18\u0e35\u0e01\u0e23 \u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content creator)            \u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e17\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d (influencer)  \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e23\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u0e07\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c            \u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e1c\u0e25\u0e34\u0e15\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e34\u0e17\u0e18\u0e34 \u0e25\u0e34\u0e02\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e2d\u0e31\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07           \u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u82b8\u8853\u30fb\u5a2f\u697d 88\/58  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e32\u0e19\u0e17\u0e2d\u0e07\u0e41\u0e17\u0e49 4 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 8 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036162\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e31\u0e01\u0e0b\u0e34\u0e21\u0e34\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e25\u0e2d\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036162 \u0e1a\u0e08.\u0e21\u0e31\u0e01\u0e0b\u0e34\u0e21\u0e34\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e25\u0e2d\u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1\/48  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c\u0e04\u0e32\u0e0b\u0e48\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 \u0e44\u0e21\u0e48\u0e23\u0e30\u0e1a\u0e38 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e2a\u0e19-\u0e2d\u0e48\u0e32\u0e07\u0e28\u0e34\u0e25\u0e32 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569036189\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e32\u0e23\u0e4c\u0e40\u0e27\u0e2a\u0e15\u0e32 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10301\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10301\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569036189 \u0e1a\u0e08.\u0e2e\u0e32\u0e23\u0e4c\u0e40\u0e27\u0e2a\u0e15\u0e32 \u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 10301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 34\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0325569001201\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e15\u0e23\u0e31\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001201 \u0e1a\u0e08.\u0e15\u0e48\u0e2d\u0e23\u0e31\u0e01\u0e15\u0e23\u0e31\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 47599 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e14\u0e47\u0e01 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 178  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0503569004509\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35168\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004509 \u0e2b\u0e08.\u0e2d\u0e42\u0e23\u0e21\u0e48\u0e32\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35168 2569-07-09 100000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 65  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0535569000742\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e23\u0e31\u0e01\u0e29\u0e4c 49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c\",\"province_ja\":\"\u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\",\"search_text\":\"0535569000742 \u0e1a\u0e08.\u0e28\u0e38\u0e20\u0e23\u0e31\u0e01\u0e29\u0e4c 49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e15\u0e23\u0e14\u0e34\u0e15\u0e16\u0e4c \u30a6\u30c3\u30bf\u30e9\u30c7\u30a3\u30c3\u30c8\u770c\"},{\"reg_no\":\"0573569002131\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e47\u0e01\u0e0a\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27\u0e01\u0e25\u0e48\u0e2d\u0e07\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56102\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56102\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002131 \u0e2b\u0e08.\u0e40\u0e14\u0e47\u0e01\u0e0a\u0e32\u0e22\u0e02\u0e49\u0e32\u0e27\u0e01\u0e25\u0e48\u0e2d\u0e07 2569-07-09 100000 56102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e1b\u0e34\u0e48\u0e19\u0e42\u0e15 \u0e02\u0e19\u0e21\u0e2b\u0e27\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u5bbf\u6cca\u30fb\u98f2\u98df 2546\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0573569002140\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002140 \u0e2b\u0e08.\u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 2569-07-09 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e36\u0e48\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e01\u0e4b\u0e27\u0e22\u0e40\u0e15\u0e35\u0e4b\u0e22\u0e27 \u0e23\u0e32\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e1c\u0e31\u0e14\u0e0b\u0e35\u0e2d\u0e34\u0e4a\u0e27 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 155\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0655569002191\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e0188 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002191 \u0e1a\u0e08.\u0e1e\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e0188 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 91  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 22 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0835569012764\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e40\u0e2d\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012764 \u0e1a\u0e08.\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e40\u0e2d\u0e08 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 100000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 210  \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 3 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0863569000411\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e2d\u0e49\u0e2d\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e16\u0e49\u0e27\u0e19\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"93293\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"93293\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0863569000411 \u0e2b\u0e08.\u0e15\u0e49\u0e19\u0e2d\u0e49\u0e2d\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e19\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e16\u0e49\u0e27\u0e19 2569-07-09 100000 93293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e44\u0e2d\u0e14\u0e35\u0e40\u0e01\u0e21 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e02\u0e32\u0e22\u0e44\u0e2d\u0e14\u0e35\u0e40\u0e01\u0e21 \u0e02\u0e32\u0e22\u0e40\u0e07\u0e34\u0e19\u0e43\u0e19\u0e40\u0e01\u0e21 \u82b8\u8853\u30fb\u5a2f\u697d 144\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569128556\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e43\u0e08\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96101\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96101\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128556 \u0e1a\u0e08.\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e43\u0e08\u0e40\u0e27\u0e25\u0e40\u0e19\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 96101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e19\u0e27\u0e14\u0e2b\u0e19\u0e49\u0e32 \u0e19\u0e27\u0e14\u0e15\u0e31\u0e27 \u0e2a\u0e1b\u0e32 \u0e19\u0e27\u0e14\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e04\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e34\u0e27\u0e1e\u0e23\u0e23\u0e13 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e1b\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 105\/1   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 f105 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128661\",\"name_th\":\"\u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e2d\u0e31\u0e25\u0e44\u0e25\u0e41\u0e2d\u0e19\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82302\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82302\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128661 \u0e1a\u0e08.\u0e1f\u0e35\u0e19\u0e34\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e34\u0e23\u0e4c\u0e2a \u0e2d\u0e31\u0e25\u0e44\u0e25\u0e41\u0e2d\u0e19\u0e0b\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 82302 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 188\/31  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e2784 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128823\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e34\u0e07 \u0e2d\u0e2d\u0e1f \u0e42\u0e1a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128823 \u0e1a\u0e08.\u0e04\u0e34\u0e07 \u0e2d\u0e2d\u0e1f \u0e42\u0e1a\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 1  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27111 (\u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e21\u0e13\u0e35) \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129323\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e19\u0e38\u0e4a\u0e01 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68102\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68102\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129323 \u0e1a\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e19\u0e38\u0e4a\u0e01 \u0e14\u0e35\u0e40\u0e27\u0e25\u0e25\u0e2d\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 68102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e02\u0e32\u0e22\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u4e0d\u52d5\u7523 230  \u0e16\u0e19\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0113569002241\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e2d\u0e14\u0e1e\u0e25\u0e31\u0e2a \u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002241 \u0e2b\u0e08.\u0e41\u0e2d\u0e14\u0e1e\u0e25\u0e31\u0e2a \u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-08 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 919\/289  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002259\",\"name_th\":\"\u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2d\u0e40\u0e25\u0e1f\u0e40\u0e1f\u0e48\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c)\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46492\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46492\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002259 \u0e2b\u0e08.\u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19 \u0e40\u0e2d\u0e40\u0e25\u0e1f\u0e40\u0e1f\u0e48\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) 2569-07-08 100000 46492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e1b\u0e25\u0e27 \u0e42\u0e25\u0e2b\u0e30\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1b\u0e25\u0e27 \u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07\u0e40\u0e1b\u0e25\u0e27 \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\u0e40\u0e1b\u0e25\u0e27  \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e04 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 24\/22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0135569021093\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46593\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46593\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569021093 \u0e1a\u0e08.\u0e44\u0e2d\u0e40\u0e2d\u0e47\u0e21\u0e0b\u0e35 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 46593 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e02\u0e49\u0e32?\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e41\u0e21\u0e0a\u0e0a\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e39\u0e07 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e25\u0e32\u0e14\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/463  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0213569001243\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e42\u0e2d\u0e1a\u0e35 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"18122\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"18122\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001243 \u0e2b\u0e08.\u0e40\u0e04\u0e42\u0e2d\u0e1a\u0e35 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 2569-07-08 100000 18122 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e41\u0e01\u0e30\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23 \u0e17\u0e33\u0e41\u0e1a\u0e1a\u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e2a\u0e31\u0e48\u0e07 \u88fd\u9020 10\/5  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e19\u0e34\u0e22\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009076\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e44\u0e17\u0e22\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009076 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e44\u0e17\u0e22\u0e40\u0e17\u0e23\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 11043 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u88fd\u9020 239\/35  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e2d\u0e30\u0e40\u0e1e\u0e23\u0e0a \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009084\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e31\u0e04\u0e20\u0e23\u0e44\u0e17\u0e22\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46107\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46107\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009084 \u0e1a\u0e08.\u0e20\u0e31\u0e04\u0e20\u0e23\u0e44\u0e17\u0e22\u0e1e\u0e31\u0e2a\u0e14\u0e38 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 46107 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 167  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009106\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e25\u0e31\u0e01\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009106 \u0e1a\u0e08.\u0e2a\u0e25\u0e31\u0e01\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e42\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 56302 \u0e40\u0e1b\u0e34\u0e14\u0e23\u0e49\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e41\u0e1f \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u5bbf\u6cca\u30fb\u98f2\u98df 36  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1b\u0e32\u0e01\u0e04\u0e25\u0e2d\u0e07 - \u0e40\u0e19\u0e34\u0e19\u0e1e\u0e22\u0e2d\u0e21 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009114\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e0a\u0e19\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e16\u0e32\u0e27\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009114 \u0e1a\u0e08.\u0e04\u0e38\u0e13\u0e0a\u0e19\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e16\u0e32\u0e27\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1b\u0e25\u0e35\u0e01-\u0e2a\u0e48\u0e07 \u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e1c\u0e34\u0e27 \u0e19\u0e4d\u0e49\u0e32\u0e2b\u0e2d\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e17\u0e34\u0e19\u0e1c\u0e34\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 521\/22  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e34\u0e25\u0e32\u0e42\u0e19 \u0e2e\u0e34\u0e25\u0e25\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0303569002630\",\"name_th\":\"\u0e2b\u0e08.\u0e1b. \u0e40\u0e08\u0e23\u0e34\u0e0d \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47612\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47612\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002630 \u0e2b\u0e08.\u0e1b. \u0e40\u0e08\u0e23\u0e34\u0e0d \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 2569-07-08 100000 47612 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 633\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0333569000645\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47591\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47591\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29\",\"province_ja\":\"\u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\",\"search_text\":\"0333569000645 \u0e2b\u0e08.\u0e40\u0e04\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e19 \u0e40\u0e27\u0e25\u0e18\u0e4c \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 2569-07-08 100000 47591 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 113  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u30b7\u30fc\u30b5\u30b1\u30fc\u30c8\u770c\"},{\"reg_no\":\"0403569002990\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002990 \u0e2b\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e22\u0e32 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-08 100000 42909 \u0e23\u0e31\u0e1a\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e01\u0e25\u0e2b\u0e19\u0e31\u0e01 \u5efa\u8a2d 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569015405\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e32\u0e42\u0e21\u0e48\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46494\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46494\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015405 \u0e1a\u0e08.\u0e01\u0e32\u0e42\u0e21\u0e48\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 46494 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 9809  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0573569002107\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002107 \u0e2b\u0e08.\u0e40\u0e2d\u0e14\u0e35\u0e40\u0e2d\u0e2a \u0e1a\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07 2569-07-08 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 71\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0675569001438\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e32\u0e04\u0e23 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001438 \u0e1a\u0e08.\u0e2a\u0e32\u0e04\u0e23 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e34\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 45302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04  \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0675569001446\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e32 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001446 \u0e1a\u0e08.\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e32 \u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e1a\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0675569001462\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e30\u0e02\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46313\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46313\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001462 \u0e1a\u0e08.\u0e21\u0e30\u0e02\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 100000 46313 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569127622\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127622 \u0e1a\u0e08.\u0e0a\u0e31\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 59111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e33 \u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01 \u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c \u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1e\u0e2d\u0e14\u0e41\u0e04\u0e2a\u0e15\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 66\/2808  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e2b\u0e30\u0e2b\u0e19\u0e2d\u0e07\u0e08\u0e2d\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 \u0e0b\u0e49\u0e32\u0e22 11 \u0e01 \u0e16\u0e19\u0e19\u0e21\u0e34\u0e15\u0e23\u0e44\u0e21\u0e15\u0e23\u0e35 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127649\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e04\u0e21\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127649 \u0e1a\u0e08.\u0e44\u0e04\u0e21\u0e21\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 44\/59  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e23\u0e34\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 69 \u0e16\u0e19\u0e19\u0e40\u0e25\u0e35\u0e22\u0e1a\u0e2f\u0e1d\u0e31\u0e48\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127703\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1a\u0e15\u0e07 \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127703 \u0e1a\u0e08.\u0e40\u0e1a\u0e15\u0e07 \u0e1a\u0e32\u0e07\u0e01\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 524\/4  \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127738\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127738 \u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e25\u0e35\u0e01\u0e31\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/44  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e1e\u0e23\u0e40\u0e27\u0e17 \u0e40\u0e19\u0e2d\u0e27\u0e32\u0e19\u0e32 \u0e40\u0e23\u0e2a\u0e0b\u0e34\u0e40\u0e14\u0e19\u0e0b\u0e4c \u0e0b\u0e2d\u0e22 \u0e42\u0e22\u0e18\u0e34\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32 11 \u0e41\u0e22\u0e01 7 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e21\u0e19\u0e39\u0e18\u0e23\u0e23\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127801\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e14\u0e0a\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46900\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46900\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127801 \u0e1a\u0e08.\u0e41\u0e14\u0e0a\u0e1e\u0e2d\u0e23\u0e4c\u0e15 \u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 46900 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (warehouse management) \u0e01\u0e32\u0e23\u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e01\u0e47\u0e15\u0e48\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e49\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1144\/8  \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e01\u0e23\u0e30\u0e1a\u0e31\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127819\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e42\u0e1f\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127819 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e2a\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e42\u0e1f\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e43\u0e19\u0e23\u0e32\u0e04\u0e32\u0e1b\u0e25\u0e35\u0e01 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 231  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 102\/3 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127860\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127860 \u0e1a\u0e08.\u0e40\u0e21\u0e2d\u0e23\u0e34\u0e40\u0e14\u0e35\u0e22\u0e19 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 744 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127959\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e38\u0e48\u0e07\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127959 \u0e1a\u0e08.\u0e1e\u0e38\u0e48\u0e07\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 73101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c(online)\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c(offline) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1a\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25(platform digital) \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 39\/83  \u0e0b\u0e2d\u0e22 \u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e2181\/6 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127975\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e34\u0e49\u0e07\u0e08\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66199\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66199\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127975 \u0e1a\u0e08.\u0e25\u0e34\u0e49\u0e07\u0e08\u0e34\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 66199 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c  \u0e40\u0e01\u0e47\u0e1a\u0e1c\u0e25\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e43\u0e2b\u0e49\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u91d1\u878d\u30fb\u4fdd\u967a 2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e2a\u0e30\u0e41\u0e01\u0e07\u0e32\u0e21\u0e0b\u0e2d\u0e22 27 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128220\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e25\u0e2d\u0e04\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128220 \u0e1a\u0e08.\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e25\u0e2d\u0e04\u0e48\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 91\/82  \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e44\u0e2b\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128319\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e1e\u0e35.\u0e0b\u0e35.\u0e2d\u0e32\u0e23\u0e4c. \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128319 \u0e1a\u0e08.\u0e1e\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e1e\u0e35.\u0e0b\u0e35.\u0e2d\u0e32\u0e23\u0e4c. \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 82199 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e02\u0e49\u0e32\u0e40\u0e21\u0e37\u0e2d\u0e07 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 54  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 52 (\u0e2a\u0e2b\u0e01\u0e23\u0e13\u0e4c2) \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128408\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e41\u0e04\u0e47\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128408 \u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e41\u0e04\u0e47\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 64202 \u0e40\u0e02\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e43\u0e19\u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19\u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e2b\u0e32\u0e0a\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u91d1\u878d\u30fb\u4fdd\u967a 388  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e2d\u0e47\u0e01\u0e40\u0e0a\u0e19 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2901-2904 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 29 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128424\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e04\u0e23 \u0e2d\u0e30\u0e1e\u0e32\u0e40\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46414\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46414\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128424 \u0e1a\u0e08.\u0e41\u0e04\u0e23 \u0e2d\u0e30\u0e1e\u0e32\u0e40\u0e23\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 46414 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04-\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 235\/4  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 31 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128441\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128441 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08\u0e2d\u0e32\u0e23\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e25 \u0e41\u0e2d\u0e2a\u0e40\u0e0b\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 96\/370  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e01\u0e25\u0e40\u0e14\u0e49\u0e19\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u0e0b\u0e2d\u0e22 01 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01 6\/2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569128521\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82199\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82199\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569128521 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e21\u0e34\u0e17 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 82199 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e33\u0e07\u0e32\u0e19 ( work permit ) \u0e27\u0e35\u0e0b\u0e48\u0e32\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 598\/30  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 87 \u0e41\u0e22\u0e01 32 \u0e16\u0e19\u0e19\u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569020950\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e21\u0e1e\u0e4c\u0e17\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020950 \u0e1a\u0e08.\u0e1e\u0e23\u0e2d\u0e21\u0e1e\u0e4c\u0e17\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e07\u0e32\u0e19\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e2d\u0e34\u0e19\u0e42\u0e1f\u0e01\u0e23\u0e32\u0e1f\u0e34\u0e01 \u0e20\u0e32\u0e1e\u0e19\u0e34\u0e48\u0e07 \u0e20\u0e32\u0e1e\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 85,20  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0225569002144\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e192 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e04\u0e23\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46692\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46692\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002144 \u0e1a\u0e08.\u0e40\u0e08\u0e192 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e04\u0e23\u0e2d\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 46692 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1b\u0e38\u0e4b\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e14\u0e34\u0e19\u0e01\u0e23\u0e30\u0e16\u0e32\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e22\u0e32\u0e06\u0e48\u0e32\u0e41\u0e21\u0e25\u0e07 \u0e22\u0e32\u0e06\u0e48\u0e32\u0e2b\u0e19\u0e39 \u0e22\u0e32\u0e06\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e23\u0e32 \u0e22\u0e32\u0e17\u0e33\u0e25\u0e32\u0e22\u0e27\u0e31\u0e0a\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 58\/19  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0245569003655\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e32\u0e25-\u0e21\u0e30-\u0e01\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0245569003655 \u0e1a\u0e08.\u0e02\u0e32\u0e25-\u0e21\u0e30-\u0e01\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17 \u0e42\u0e2e\u0e21\u0e2a\u0e40\u0e15\u0e22\u0e4c \u0e1e\u0e25\u0e39\u0e27\u0e34\u0e25\u0e25\u0e48\u0e32 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e01\u0e2a\u0e15\u0e4c\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e23\u0e32\u0e22\u0e27\u0e31\u0e19 \u0e23\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 43\/3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0305569007056\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e42\u0e1f\u0e23\u0e4c\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0305569007056 \u0e1a\u0e08.\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e42\u0e1f\u0e23\u0e4c\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 63112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e0a\u0e23\u0e4c\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e2e\u0e25\u0e15\u0e34\u0e49\u0e07\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 488\/2  \u0e0b\u0e2d\u0e22 \u0e19\u0e34\u0e04\u0e21\u0e25\u0e33\u0e15\u0e30\u0e04\u0e2d\u0e07 3 \u0e16\u0e19\u0e19\u0e19\u0e34\u0e04\u0e21\u0e25\u0e33\u0e15\u0e30\u0e04\u0e2d\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0423569000407\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e28\u0e34\u0e23\u0e34\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e25\u0e22\",\"province_ja\":\"\u30eb\u30fc\u30a4\u770c\",\"search_text\":\"0423569000407 \u0e2b\u0e08.\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e28\u0e34\u0e23\u0e34 2569-07-07 100000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 173  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e31\u0e19\u0e15\u0e34\u0e20\u0e32\u0e1e\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e40\u0e25\u0e22 \u30eb\u30fc\u30a4\u770c\"},{\"reg_no\":\"0443569000725\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000725 \u0e2b\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e17\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 2569-07-07 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 10\/14  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e21\u0e16\u0e27\u0e34\u0e25 9 \u0e16\u0e19\u0e19\u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e2a\u0e21\u0e16\u0e27\u0e34\u0e25 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0605569001934\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e25\u0e31\u0e04\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0605569001934 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e48\u0e32 \u0e25\u0e31\u0e04\u0e04\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u60c5\u5831\u901a\u4fe1\u30fbit 2012\/12  \u0e0b\u0e2d\u0e22 \u0e23\u0e27\u0e21\u0e43\u0e08 2 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0735569006862\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e17\u0e04\u0e40\u0e04\u0e34\u0e25\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47630\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47630\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006862 \u0e1a\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e47\u0e19\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e17\u0e04\u0e40\u0e04\u0e34\u0e25\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 47630 \u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e35\u0e2c\u0e32\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e40\u0e09\u0e1e\u0e32\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 120\/143  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0745569007109\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46622\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46622\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569007109 \u0e1a\u0e08.\u0e40\u0e2e\u0e07 \u0e40\u0e2e\u0e07 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e01\u0e34\u0e08 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 100000 46622 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e40\u0e2b\u0e25\u0e47\u0e01\u0e40\u0e1e\u0e25\u0e17 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e41\u0e25\u0e30\u0e42\u0e25\u0e2b\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 168  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569126863\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126863 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e27\u0e35\u0e2d\u0e35\u0e40\u0e2d\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e25 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e02\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 21\/6  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 34 \u0e41\u0e22\u0e01 19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127207\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e01\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127207 \u0e1a\u0e08.\u0e0a\u0e38\u0e19\u0e01\u0e35\u0e48 \u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 101\/71  \u0e16\u0e19\u0e19\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127291\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e18\u0e31\u0e0d \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127291 \u0e1a\u0e08.\u0e28\u0e34\u0e27\u0e18\u0e31\u0e0d \u0e04\u0e2d\u0e23\u0e4c\u0e1b\u0e2d\u0e40\u0e23\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e27\u0e34\u0e19\u0e32\u0e28\u0e20\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 44\/27  \u0e0b\u0e2d\u0e22 \u0e19\u0e27\u0e21\u0e34\u0e19\u0e17\u0e23\u0e4c 149 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127461\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77305\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77305\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127461 \u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e2d\u0e35\u0e04\u0e27\u0e34\u0e1b\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 77305 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e48\u0e27\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 577  \u0e16\u0e19\u0e19\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127487\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e47\u0e04\u0e15\u0e4c 11 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127487 \u0e1a\u0e08.\u0e44\u0e1e\u0e19\u0e4c\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e42\u0e1b\u0e23\u0e40\u0e08\u0e47\u0e04\u0e15\u0e4c 11 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23 \u0e16\u0e19\u0e19 \u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e17\u0e32\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e25\u0e32\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e39\u0e1b\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 577  \u0e16\u0e19\u0e19\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569127495\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e44\u0e1e\u0e19\u0e4c\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0105569127495 \u0e1a\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e44\u0e1e\u0e19\u0e4c\u0e22\u0e32\u0e23\u0e4c\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e01\u0e48\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2d\u0e37\u0e48\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 989  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569127509\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e32\u0e19\u0e18\u0e32 5 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127509 \u0e1a\u0e08.\u0e04\u0e32\u0e19\u0e18\u0e32 5 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e19\u0e32\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e41\u0e25\u0e30\u0e43\u0e19\u0e19\u0e32\u0e21\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e23\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u60c5\u5831\u901a\u4fe1\u30fbit 159\/3  \u0e0b\u0e2d\u0e22 \u0e21\u0e2b\u0e32\u0e14\u0e40\u0e25\u0e47\u0e01\u0e2b\u0e25\u0e27\u0e07 2 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e23\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569022162\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e22 \u0e2a\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022162 \u0e1a\u0e08.\u0e21\u0e32\u0e22 \u0e2a\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/3  \u0e0b\u0e2d\u0e22 8 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e22\u0e25\u0e27\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569022189\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e27\u0e34\u0e1f\u0e15\u0e4c \u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47525\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47525\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022189 \u0e1a\u0e08.\u0e2a\u0e27\u0e34\u0e1f\u0e15\u0e4c \u0e0a\u0e31\u0e27\u0e23\u0e4c \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 47525 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e0a\u0e48\u0e32\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e2a\u0e35 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e2d\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 81\/51  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e28\u0e38\u0e20\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e27\u0e34\u0e27\u0e25\u0e4c (\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c-\u0e1a\u0e32\u0e07\u0e19\u0e32) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e0b\u0e2d\u0e22 \u0e28\u0e23\u0e35\u0e14\u0e48\u0e32\u0e19 22 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569025081\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025081 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e2d\u0e2a\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07 \u0e07\u0e32\u0e19\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c \u82b8\u8853\u30fb\u5a2f\u697d 94\/41  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569025226\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19\u0e2d\u0e22\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025226 \u0e1a\u0e08.\u0e2e\u0e34\u0e27\u0e41\u0e21\u0e19\u0e2d\u0e22\u0e14\u0e4c \u0e40\u0e17\u0e23\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 59\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569035417\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1f\u0e21 \u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47222\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47222\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569035417 \u0e1a\u0e08.\u0e41\u0e1f\u0e21 \u0e17\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 47222 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 53\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0503569004380\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e1e\u0e31\u0e0b\u0e40\u0e0b\u0e34\u0e25\u0e2a\u0e4c\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"16101\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"16101\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004380 \u0e2b\u0e08.\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e1e\u0e31\u0e0b\u0e40\u0e0b\u0e34\u0e25\u0e2a\u0e4c 2569-07-06 100000 16101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e44\u0e2a\u0e44\u0e21\u0e49\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e44\u0e21\u0e49 \u0e42\u0e23\u0e07\u0e40\u0e25\u0e37\u0e48\u0e2d\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u88fd\u9020 445  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0655569002124\",\"name_th\":\"\u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e40\u0e27\u0e25 \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002124 \u0e1a\u0e08.\u0e28\u0e34\u0e23\u0e34 \u0e40\u0e27\u0e25 \u0e44\u0e25\u0e1f\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 240\/14  \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e02\u0e32\u0e27 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0905569005325\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e41\u0e14\u0e07 \u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e1f\u0e39\u0e49\u0e14\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10304\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10304\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005325 \u0e1a\u0e08.\u0e40\u0e08\u0e4a\u0e41\u0e14\u0e07 \u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u0e1f\u0e39\u0e49\u0e14\u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 100000 10304 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e0b\u0e2d\u0e22 \u0e40\u0e08\u0e35\u0e22\u0e27 \u0e1a\u0e14 \u0e04\u0e31\u0e14\u0e41\u0e22\u0e01 \u0e41\u0e25\u0e30\u0e15\u0e23\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2b\u0e31\u0e27\u0e2b\u0e2d\u0e21\u0e41\u0e14\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u88fd\u9020 4  \u0e0b\u0e2d\u0e22 8 \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e16\u0e19\u0e19\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e27\u0e13\u0e34\u0e0a\u0e22\u0e4c \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0225569002110\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47723\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47723\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0225569002110 \u0e1a\u0e08.\u0e20\u0e31\u0e17\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e19\u0e31\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-05 100000 47723 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e08\u0e31\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e3\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0603569001479\",\"name_th\":\"\u0e2b\u0e08.\u0e14\u0e35\u0e1f\u0e39\u0e4a\u0e14\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c\",\"reg_date\":\"2569-07-05\",\"reg_date_sort\":25690705,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001479 \u0e2b\u0e08.\u0e14\u0e35\u0e1f\u0e39\u0e4a\u0e14\u0e04\u0e23\u0e32\u0e1f\u0e17\u0e4c 2569-07-05 100000 56101 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e19\u0e17\u0e19\u0e32\u0e01\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 125\/10  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0105569126626\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e19\u0e34\u0e01\u0e0b\u0e4c\u0e42\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126626 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e19\u0e34\u0e01\u0e0b\u0e4c\u0e42\u0e19\u0e27\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 100000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1b\u0e38\u0e4b\u0e22 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e2d\u0e31\u0e19\u0e15\u0e23\u0e32\u0e22\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e2a\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e28\u0e31\u0e15\u0e23\u0e39\u0e1e\u0e37\u0e0a \u0e2a\u0e32\u0e23\u0e01\u0e33\u0e08\u0e31\u0e14\u0e27\u0e31\u0e0a\u0e1e\u0e37\u0e0a \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14 \u0e42\u0e23\u0e04\u0e1e\u0e37\u0e0a\u0e01\u0e23\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e36\u0e49\u0e19\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 17\/3  \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 54 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126642\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e17\u0e17\u0e2d\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126642 \u0e1a\u0e08.\u0e41\u0e2d\u0e17\u0e17\u0e2d\u0e2a \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 100000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e43\u0e14 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e44\u0e27\u0e49\u0e43\u0e0a\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e02\u0e2d \u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15 \u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e08\u0e33\u0e19\u0e33 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e08\u0e31\u0e14\u0e2b\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2e\u0e32\u0e23\u0e4c\u0e15\u0e41\u0e27\u0e23\u0e4c\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0b\u0e2d\u0e1f\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21 \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e23\u0e30\u0e1a\u0e1a \u0e15\u0e39\u0e49\u0e2a\u0e32\u0e02\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e1a\u0e31\u0e15\u0e34 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e1b\u0e25\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e22\u0e2d\u0e14\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e15\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e1c\u0e48\u0e32\u0e19\u0e14\u0e32\u0e27\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e43\u0e22\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e25 \u0e2a\u0e32\u0e22\u0e17\u0e2d\u0e07\u0e41\u0e14\u0e07 \u0e40\u0e2a\u0e32\u0e2a\u0e48\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e2a\u0e32\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e02\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e02\u0e2d\u0e07 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e15\u0e2d\u0e1a\u0e23\u0e31\u0e1a (call center) \u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/721  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e0b\u0e2d\u0e22 82 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569126651\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e35\u0e42\u0e19\u0e48 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47640\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47640\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126651 \u0e1a\u0e08.\u0e08\u0e35\u0e42\u0e19\u0e48 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 100000 47640 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 253\/136  \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e41\u0e27\u0e01 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0185569000479\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08555 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42909\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42909\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\",\"search_text\":\"0185569000479 \u0e1a\u0e08.\u0e1e\u0e35\u0e40\u0e08555 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 100000 42909 \u0e23\u0e31\u0e1a\u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32 \u5efa\u8a2d 835  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e0a\u0e31\u0e22\u0e19\u0e32\u0e17 \u30c1\u30e3\u30a4\u30ca\u30fc\u30c8\u770c\"},{\"reg_no\":\"0503569004355\",\"name_th\":\"\u0e2b\u0e08.\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47722\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47722\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004355 \u0e2b\u0e08.\u0e41\u0e01\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e35\u0e48\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21 2569-07-04 100000 47722 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e0b\u0e48\u0e2d\u0e21\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (vending machine) \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33\u0e2b\u0e2d\u0e21\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 184  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569126189\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e39\u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"66191\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"66191\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126189 \u0e1a\u0e08.\u0e08\u0e39\u0e1b\u0e35\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e15\u0e34\u0e49\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 66191 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u91d1\u878d\u30fb\u4fdd\u967a 1788  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3001-3003,3009-3014 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021921\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e14\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021921 \u0e1a\u0e08.\u0e40\u0e2d\u0e14\u0e40\u0e27\u0e19\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25\u0e15\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88\/242  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 atoll maldives palms \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e27\u0e07\u0e40\u0e40\u0e2b\u0e27\u0e19 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021930\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e25\u0e39\u0e40\u0e2d\u0e17 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021930 \u0e1a\u0e08.\u0e0b\u0e34\u0e25\u0e25\u0e39\u0e40\u0e2d\u0e17 \u0e2e\u0e31\u0e1a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25 \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e42\u0e1e\u0e25\u0e32\u0e23\u0e2d\u0e22\u0e14\u0e4c \u0e01\u0e25\u0e49\u0e2d\u0e07action cam \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07  \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e48\u0e2d\u0e1e\u0e48\u0e27\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024777\",\"name_th\":\"\u0e1a\u0e08.101 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024777 \u0e1a\u0e08.101 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e1f\u0e23\u0e19\u0e14\u0e4c\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 56210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e19\u0e15\u0e4c (event) \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e07\u0e32\u0e19\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e2d\u0e1b (workshop) \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 199\/113  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e2a\u0e32\u0e17\u0e23 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e0b\u0e2d\u0e22 1\/10 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024912\",\"name_th\":\"\u0e1a\u0e08.\u0e08\u0e31\u0e2a\u0e15\u0e4c \u0e21\u0e32\u0e22\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024912 \u0e1a\u0e08.\u0e08\u0e31\u0e2a\u0e15\u0e4c \u0e21\u0e32\u0e22\u0e14\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e0b\u0e2d\u0e22 \u0e40\u0e23\u0e27\u0e14\u0e3532 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024939\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e1f\u0e23\u0e35\u0e48 \u0e1e\u0e23\u0e34\u0e19\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024939 \u0e1a\u0e08.\u0e41\u0e1f\u0e23\u0e35\u0e48 \u0e1e\u0e23\u0e34\u0e19\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e02\u0e47\u0e21\u0e02\u0e31\u0e14 \u0e1c\u0e49\u0e32\u0e1e\u0e31\u0e19\u0e04\u0e2d \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 108\/8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024963\",\"name_th\":\"\u0e1a\u0e08.\u0e16\u0e49\u0e33\u0e2a\u0e34\u0e07\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024963 \u0e1a\u0e08.\u0e16\u0e49\u0e33\u0e2a\u0e34\u0e07\u0e42\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 92\/91  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e41\u0e1e\u0e25\u0e19\u0e17\u0e4c \u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008932\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e39\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008932 \u0e1a\u0e08.\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e39\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e19\u0e21\u0e44\u0e02\u0e48\u0e21\u0e38\u0e01 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e0a\u0e32\u0e19\u0e21 \u0e01\u0e32\u0e41\u0e1f \u5bbf\u6cca\u30fb\u98f2\u98df 22\/5  \u0e0b\u0e2d\u0e22 \u0e2b\u0e19\u0e2d\u0e07\u0e41\u0e15\u0e07\u0e42\u0e21 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0243569000654\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 16\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49329\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49329\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000654 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e17\u0e35 \u0e01\u0e23\u0e38\u0e4a\u0e1b 16 2569-07-03 100000 49329 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e15\u0e39\u0e49\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e19\u0e31\u0e01\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e23\u0e16\u0e15\u0e39\u0e49 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e16\u0e15\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 16\/2  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0465569000824\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000824 \u0e1a\u0e08.\u0e21\u0e35\u0e40\u0e07\u0e34\u0e19\u0e44\u0e21\u0e48\u0e2b\u0e22\u0e38\u0e14 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e39\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32 (content creator) \u0e2d\u0e34\u0e19\u0e1f\u0e25\u0e39\u0e40\u0e2d\u0e19\u0e40\u0e0b\u0e2d\u0e23\u0e4c (influencer)  \u0e19\u0e31\u0e01\u0e41\u0e2a\u0e14\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e1a\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e15\u0e01\u0e25\u0e07\u0e27\u0e48\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c \u0e23\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 518  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0615569000466\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35-\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"35101\",\"industry_category\":\"\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"industry_label\":\"35101\uff5c\u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0615569000466 \u0e1a\u0e08.\u0e40\u0e04\u0e1e\u0e35-\u0e40\u0e17\u0e04 \u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e25\u0e4c \u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 35101 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e08\u0e32\u0e01\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e07\u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e37\u0e48\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e19\u0e49\u0e33 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e25\u0e21 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19 \u96fb\u6c17\u30fb\u30ac\u30b9\u30fb\u30a8\u30cd\u30eb\u30ae\u30fc 11  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0765569001402\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e19\u0e1e\u0e31\u0e19 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001402 \u0e1a\u0e08.\u0e1e\u0e31\u0e19\u0e1e\u0e31\u0e19 \u0e1a\u0e34\u0e2a\u0e0b\u0e34\u0e40\u0e19\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e35 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0835569012420\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35-\u0e42\u0e14\u0e23\u0e19 \u0e1b\u0e48\u0e32\u0e15\u0e2d\u0e07 \u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59121\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59121\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012420 \u0e1a\u0e08.\u0e1a\u0e35-\u0e42\u0e14\u0e23\u0e19 \u0e1b\u0e48\u0e32\u0e15\u0e2d\u0e07 \u0e44\u0e14\u0e19\u0e32\u0e21\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 59121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e04\u0e25\u0e34\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e32\u0e23\u0e32\u0e40\u0e0a\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e08\u0e47\u0e15\u0e2a\u0e01\u0e35 \u0e1a\u0e32\u0e19\u0e48\u0e32\u0e19\u0e48\u0e32\u0e42\u0e1a\u0e4a\u0e17 \u0e2a\u0e15\u0e23\u0e2d\u0e21 \u0e42\u0e1a\u0e4a\u0e17 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e15\u0e48\u0e2d\u0e04\u0e25\u0e34\u0e1b\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u60c5\u5831\u901a\u4fe1\u30fbit 47  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e23\u0e21\u0e35 6 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e23\u0e21\u0e35 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0865569001169\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08 \u0e20\u0e31\u0e17\u0e23 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45401\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45401\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23\",\"province_ja\":\"\u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\",\"search_text\":\"0865569001169 \u0e1a\u0e08.\u0e40\u0e08 \u0e20\u0e31\u0e17\u0e23 \u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 100000 45401 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 122\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e0a\u0e38\u0e21\u0e1e\u0e23 \u30c1\u30e5\u30e0\u30dd\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569124852\",\"name_th\":\"\u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27\u0e40\u0e2e\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124852 \u0e1a\u0e08.\u0e02\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27\u0e40\u0e2e\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 48  \u0e0b\u0e2d\u0e22 \u0e40\u0e09\u0e25\u0e34\u0e21\u0e1e\u0e23\u0e30\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34 \u0e23.\u0e59 \u0e0b.6 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124917\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e0b\u0e25 \u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124917 \u0e1a\u0e08.\u0e42\u0e0b\u0e25 \u0e04\u0e23\u0e32\u0e1f\u0e15\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e37\u0e48\u0e2d\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 6   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 610 \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 86 \u0e41\u0e22\u0e01 2 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125107\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125107 \u0e1a\u0e08.\u0e2a\u0e38\u0e02\u0e2a\u0e07\u0e04\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e22\u0e32\u0e22\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 161\/58  \u0e16\u0e19\u0e19\u0e17\u0e31\u0e1a\u0e22\u0e32\u0e27 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125344\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e29\u0e0e\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e1e\u0e23\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47599\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47599\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125344 \u0e1a\u0e08.\u0e40\u0e08\u0e29\u0e0e\u0e32 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e1e\u0e23\u0e14\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 47599 \u0e2a\u0e31\u0e48\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 299  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e04\u0e25\u0e2d\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07 15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125573\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e34\u0e07\u0e04\u0e4c \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125573 \u0e1a\u0e08.\u0e18\u0e34\u0e07\u0e04\u0e4c \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 62011 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c (software as a service - saas) \u60c5\u5831\u901a\u4fe1\u30fbit 77\/5  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e27\u0e34\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125611\",\"name_th\":\"\u0e1a\u0e08.\u0e13\u0e21\u0e2d\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125611 \u0e1a\u0e08.\u0e13\u0e21\u0e2d\u0e19\u0e34\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c) \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 25  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e31\u0e25\u0e21\u0e48\u0e32 \u0e25\u0e34\u0e07\u0e04\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 734 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 \u0e0a\u0e34\u0e14\u0e25\u0e21 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e08\u0e34\u0e15 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021808\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e1a\u0e35 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e0b\u0e2d\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021808 \u0e1a\u0e08.\u0e40\u0e08\u0e1a\u0e35 \u0e2a\u0e15\u0e32\u0e23\u0e4c \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e0b\u0e2d\u0e2a\u0e0b\u0e34\u0e48\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e40\u0e0a\u0e48\u0e32\u0e0b\u0e37\u0e49\u0e2d \u0e42\u0e2d\u0e19 \u0e08\u0e33\u0e19\u0e2d\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e2d\u0e32\u0e17\u0e34 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u4e0d\u52d5\u7523 199\/2972  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021816\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"33200\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"33200\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021816 \u0e1a\u0e08.\u0e0a\u0e31\u0e22\u0e27\u0e34\u0e17\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 33200 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u88fd\u9020 9\/349  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e28\u0e23\u0e35\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0133569002208\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e27\u0e23\u0e2a \u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0133569002208 \u0e2b\u0e08.\u0e2a\u0e27\u0e23\u0e2a \u0e25\u0e2d\u0e19\u0e14\u0e23\u0e35\u0e49 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-02 100000 96201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e2d\u0e1a\u0e23\u0e35\u0e14\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e1c\u0e49\u0e32\u0e1b\u0e39\u0e17\u0e35\u0e48\u0e19\u0e2d\u0e19 \u0e1b\u0e25\u0e2d\u0e01\u0e2b\u0e21\u0e2d\u0e19 \u0e1c\u0e49\u0e32\u0e40\u0e0a\u0e47\u0e14\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e1c\u0e49\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e1c\u0e49\u0e32 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e2a\u0e1b\u0e32\u0e41\u0e25\u0e30\u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a\u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e14\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e15\u0e31\u0e14\u0e1c\u0e21 \u0e41\u0e15\u0e48\u0e07\u0e1c\u0e21 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e27\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 97\/104  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0405569006300\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63111\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63111\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006300 \u0e1a\u0e08.\u0e04\u0e25\u0e32\u0e27\u0e14\u0e4c\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 63111 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 35  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 19 \u0e16\u0e19\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e49\u0e07 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0413569001489\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e23\u0e34\u0e0a \u0e23\u0e35\u0e27\u0e34\u0e27\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"58192\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"58192\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0413569001489 \u0e2b\u0e08.\u0e2a\u0e01\u0e32\u0e22 \u0e23\u0e34\u0e0a \u0e23\u0e35\u0e27\u0e34\u0e27 2569-07-02 100000 58192 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e23\u0e35\u0e27\u0e34\u0e27 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e42\u0e06\u0e29\u0e13\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 54\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0443569000695\",\"name_th\":\"\u0e2b\u0e08.\u0e2d\u0e21\u0e23\u0e44\u0e0a\u0e17\u0e27\u0e35\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"28219\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"28219\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0443569000695 \u0e2b\u0e08.\u0e2d\u0e21\u0e23\u0e44\u0e0a\u0e17\u0e27\u0e35 2569-07-02 100000 28219 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e07\u0e32\u0e19\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07,\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e08\u0e23\u0e32\u0e08\u0e23,\u0e07\u0e32\u0e19\u0e2a\u0e35\u0e15\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e08\u0e23\u0e32\u0e08\u0e23, \u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07,\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e42\u0e0b\u0e25\u0e48\u0e32\u0e40\u0e0b\u0e25\u0e4c,\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46,\u0e07\u0e32\u0e19\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c,\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23,\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e31\u0e14\u0e40\u0e2b\u0e25\u0e47\u0e01,\u0e22\u0e32\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c,\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e2b\u0e25\u0e48\u0e2d\u0e25\u0e37\u0e48\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e15\u0e48\u0e32\u0e07\u0e46 \u88fd\u9020 69  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e15\u0e30\u0e04\u0e38 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0623569000685\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e04\u0e33\u0e40\u0e21\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"42101\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"42101\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23\",\"province_ja\":\"\u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\",\"search_text\":\"0623569000685 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e04\u0e33\u0e40\u0e21\u0e37\u0e2d\u0e07 2569-07-02 100000 42101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 (\u0e04\u0e2a\u0e25.) \u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07\u0e41\u0e25\u0e30\u0e16\u0e19\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 619  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e01\u0e33\u0e41\u0e1e\u0e07\u0e40\u0e1e\u0e0a\u0e23 \u30ab\u30e0\u30da\u30fc\u30f3\u30da\u30c3\u30c8\u770c\"},{\"reg_no\":\"0735569006706\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e44\u0e2d\u0e41\u0e2d\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46105\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46105\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006706 \u0e1a\u0e08.\u0e1e\u0e35\u0e44\u0e2d\u0e41\u0e2d\u0e25 \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 100000 46105 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e01\u0e25 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e38\u0e48\u0e19\u0e41\u0e23\u0e07 \u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e40\u0e19\u0e34\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e39\u0e1a\u0e19\u0e49\u0e33 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e33\u0e1a\u0e31\u0e14\u0e19\u0e49\u0e33\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e33\u0e08\u0e31\u0e14\u0e02\u0e22\u0e30 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 14\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0103569006475\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e19 \u0e27\u0e34\u0e19 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47114\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47114\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006475 \u0e2b\u0e08.\u0e27\u0e34\u0e19 \u0e27\u0e34\u0e19 \u0e23\u0e38\u0e48\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e07 2569-07-01 100000 47114 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e49\u0e32\u0e27\u0e2a\u0e32\u0e23 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e02\u0e19\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e23\u0e27\u0e21\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b\u0e08\u0e33\u0e1e\u0e27\u0e01\u0e1b\u0e25\u0e32\u0e2b\u0e21\u0e36\u0e01\u0e41\u0e1c\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 155  \u0e0b\u0e2d\u0e22 \u0e25\u0e32\u0e14\u0e1e\u0e23\u0e49\u0e32\u0e27 64 \u0e41\u0e22\u0e01 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123694\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e48\u0e21\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"77299\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"77299\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123694 \u0e1a\u0e08.\u0e23\u0e48\u0e21\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 77299 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e48\u0e21 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14 \u0e01\u0e31\u0e19\u0e1d\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 9\/9  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 46 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123813\",\"name_th\":\"\u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2d\u0e39\u0e49\u0e1f\u0e39\u0e48\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47219\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47219\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123813 \u0e1a\u0e08.\u0e23\u0e27\u0e22\u0e2d\u0e39\u0e49\u0e1f\u0e39\u0e48\u0e44\u0e21\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 47219 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e02\u0e19\u0e21\u0e02\u0e1a\u0e40\u0e04\u0e35\u0e49\u0e22\u0e27 \u0e16\u0e31\u0e48\u0e27 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e41\u0e25\u0e30\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 123\/345  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123821\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e44\u0e2d\u0e0b\u0e4c \u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123821 \u0e1a\u0e08.\u0e0b\u0e31\u0e19\u0e44\u0e2d\u0e0b\u0e4c \u0e2a\u0e2d\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 98\/145  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e41\u0e25\u0e19\u0e0b\u0e34\u0e42\u0e2d (\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32-\u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e25) \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123872\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123872 \u0e1a\u0e08.\u0e17\u0e35\u0e17\u0e35\u0e41\u0e2d\u0e25 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e02\u0e2d\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02\u0e2d\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32  \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 110   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 2-1 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 66\/1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123899\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e2d\u0e1768 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59121\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59121\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123899 \u0e1a\u0e08.\u0e14\u0e2d\u0e1768 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 59121 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e2a\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e1f\u0e44\u0e25\u0e19\u0e4c \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e15\u0e15\u0e34\u0e49\u0e07 \u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e15\u0e15\u0e34\u0e49\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u60c5\u5831\u901a\u4fe1\u30fbit 6  \u0e0b\u0e2d\u0e22 15\/1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 2 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569123996\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e27\u0e25 \u0e0b\u0e39\u0e1e\u0e23\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569123996 \u0e1a\u0e08.\u0e41\u0e21\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e27\u0e25 \u0e0b\u0e39\u0e1e\u0e23\u0e35\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 65\/450  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e18\u0e31\u0e19\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e1c\u0e14\u0e38\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e4c 11 \u0e16\u0e19\u0e19\u0e1c\u0e14\u0e38\u0e07\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124020\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124020 \u0e1a\u0e08.\u0e44\u0e17\u0e22 \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\u0e2a\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\/\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e15\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e16\u0e19\u0e19\u0e2a\u0e30\u0e1e\u0e32\u0e19 \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c\u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19\u0e07\u0e32\u0e19\u0e42\u0e22\u0e23\u0e32\u0e41\u0e25\u0e30 \u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e01\u0e32\u0e23\u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e0d\u52d5\u7523 37  \u0e0b\u0e2d\u0e22 \u0e40\u0e25\u0e35\u0e22\u0e1a\u0e2f\u0e1d\u0e31\u0e48\u0e07\u0e43\u0e15\u0e49 1 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124038\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e27\u0e2c\u0e32\u0e01\u0e32\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124038 \u0e1a\u0e08.\u0e40\u0e27\u0e2c\u0e32\u0e01\u0e32\u0e22\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 1559\/310  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e04  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 310 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 8 \u0e16\u0e19\u0e19\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e19\u0e04\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124399\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e17\u0e01\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124399 \u0e1a\u0e08.\u0e27\u0e31\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e17\u0e01\u0e25\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 82\/108  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124488\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e40\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47691\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47691\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124488 \u0e1a\u0e08.\u0e14\u0e34 \u0e04\u0e23\u0e35\u0e40\u0e2d\u0e17\u0e35\u0e1f \u0e40\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 47691 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e02\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e48\u0e27\u0e22 \u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e31\u0e15\u0e16\u0e01\u0e23\u0e23\u0e21 \u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/11-16   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1b\u0e23\u0e32\u0e23\u0e20 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124496\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e34 \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46412\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46412\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124496 \u0e1a\u0e08.\u0e14\u0e34 \u0e40\u0e14\u0e04\u0e04\u0e2d\u0e23\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e0b\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 46412 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e2a\u0e31\u0e48\u0e07\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e21\u0e39\u0e48\u0e25\u0e35\u0e48 \u0e21\u0e48\u0e32\u0e19\u0e1b\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07 \u0e21\u0e48\u0e32\u0e19\u0e21\u0e49\u0e27\u0e19 \u0e09\u0e32\u0e01\u0e01\u0e31\u0e49\u0e19\u0e2b\u0e49\u0e2d\u0e07 \u0e23\u0e32\u0e07\u0e21\u0e48\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19 \u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 82\/11-16   \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1b\u0e23\u0e32\u0e23\u0e20 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569021557\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e1b\u0e30\u0e1b\u0e4a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70201\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70201\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021557 \u0e1a\u0e08.\u0e25\u0e39\u0e01\u0e1b\u0e30\u0e1b\u0e4a\u0e32 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 70201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e37\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 98\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021565\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021565 \u0e1a\u0e08.\u0e21\u0e32\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e41\u0e21\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e40\u0e0a\u0e48\u0e19 \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e02\u0e32\u0e22\u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2a\u0e38\u0e23\u0e32 \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e25\u0e01\u0e2d\u0e2e\u0e2d\u0e25\u0e4c \u5bbf\u6cca\u30fb\u98f2\u98df 333\/82  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e34\u0e23\u0e15\u0e34 \u0e1a\u0e32\u0e07\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569021689\",\"name_th\":\"\u0e1a\u0e08.\u0e2b\u0e25\u0e35 \u0e08\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569021689 \u0e1a\u0e08.\u0e2b\u0e25\u0e35 \u0e08\u0e34\u0e07 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e19\u0e25 \u0e40\u0e2d\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e08\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e15\u0e32\u0e21 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e41\u0e25\u0e49\u0e27 \u91d1\u878d\u30fb\u4fdd\u967a 133\/311  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0125569024475\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e35\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45301\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45301\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024475 \u0e1a\u0e08.\u0e21\u0e35\u0e1e\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 45301 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95\/125  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024483\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e19\u0e0b\u0e4c\u0e40\u0e01\u0e34\u0e25\u0e2a\u0e4c\u0e40\u0e01\u0e17\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024483 \u0e1a\u0e08.\u0e44\u0e19\u0e0b\u0e4c\u0e40\u0e01\u0e34\u0e25\u0e2a\u0e4c\u0e40\u0e01\u0e17\u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/126  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0125569024548\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e2d\u0e32\u0e40\u0e15\u0e2d\u0e25\u0e34\u0e40\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569024548 \u0e1a\u0e08.\u0e15\u0e23\u0e35\u0e1e\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e1a\u0e34\u0e27\u0e15\u0e35\u0e49 \u0e2d\u0e32\u0e40\u0e15\u0e2d\u0e25\u0e34\u0e40\u0e22\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 96309 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e32\u0e27\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e38\u0e14\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e32\u0e27 \u0e2a\u0e2d\u0e19\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 96\/21  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e2d\u0e25 \u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21 5 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e2b\u0e39\u0e0a\u0e49\u0e32\u0e07-\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e17\u0e1e\u0e28\u0e34\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e16\u0e19\u0e19\u0e19\u0e04\u0e23\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020151\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85422\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85422\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020151 \u0e1a\u0e08.\u0e21\u0e34\u0e27\u0e2a\u0e34\u0e04\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 85422 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e43\u0e19\u0e2a\u0e32\u0e02\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e14\u0e49\u0e32\u0e19\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e28\u0e34\u0e25\u0e1b\u0e30 \u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e2d\u0e1b \u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e31\u0e01\u0e29\u0e30\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e17\u0e38\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a \u6559\u80b2 52\/554  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e2d\u0e01 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e40\u0e2d\u0e01\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13 5 \u0e16\u0e19\u0e19\u0e1e\u0e2b\u0e25\u0e42\u0e22\u0e18\u0e34\u0e19 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0135569020186\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e18\u0e23\u0e32\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62023\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62023\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020186 \u0e1a\u0e08.\u0e44\u0e18\u0e23\u0e32\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 62023 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u60c5\u5831\u901a\u4fe1\u30fbit 168\/3  \u0e2d\u0e32\u0e04\u0e32\u0e23b1 \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e04\u0e34\u0e17\u0e17\u0e4c \u0e44\u0e25\u0e17\u0e4c \u0e1a\u0e32\u0e07\u0e01\u0e30\u0e14\u0e35-\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e16\u0e19\u0e19\u0e15\u0e34\u0e27\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0145569004334\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e4c\u0e2d\u0e2d\u0e1b\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"80200\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"80200\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32\",\"province_ja\":\"\u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\",\"search_text\":\"0145569004334 \u0e1a\u0e08.\u0e0b\u0e35\u0e40\u0e04\u0e35\u0e22\u0e27\u0e23\u0e4c\u0e2d\u0e2d\u0e1b\u0e2a\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 80200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 saas \u0e23\u0e30\u0e1a\u0e1a\u0e21\u0e2d\u0e19\u0e34\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e14\u0e0a\u0e1a\u0e2d\u0e23\u0e4c\u0e14 \u0e41\u0e08\u0e49\u0e07\u0e40\u0e15\u0e37\u0e2d\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e2a\u0e19\u0e32\u0e21 \u0e07\u0e32\u0e19\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21 \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e07\u0e32\u0e19\u0e15\u0e23\u0e27\u0e08\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e07\u0e32\u0e19\u0e25\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 209\/79  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e2a\u0e34\u0e23\u0e34 \u0e19\u0e04\u0e23\u0e2b\u0e25\u0e27\u0e072 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e0b\u0e2d\u0e22 \u0e20\u0e39\u0e21\u0e34\u0e2a\u0e34\u0e23\u0e34 8 \u0e16\u0e19\u0e19\u0e17\u0e32\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e0233 \u0e08.\u0e1e\u0e23\u0e30\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u30d7\u30e9\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30fb\u30a2\u30e6\u30bf\u30e4\u30fc\u770c\"},{\"reg_no\":\"0205569034526\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e34\u0e18 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034526 \u0e1a\u0e08.\u0e40\u0e0b\u0e19\u0e34\u0e18 \u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e2a\u0e33\u0e23\u0e27\u0e08 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07 \u0e41\u0e1b\u0e23\u0e2a\u0e20\u0e32\u0e1e \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1c\u0e25\u0e34\u0e14 \u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2a\u0e30\u0e2a\u0e21 \u0e2a\u0e33\u0e23\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e19\u0e49\u0e33 \u0e25\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14 \u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e27\u0e48\u0e32 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e04\u0e21\u0e35\u0e08\u0e32\u0e01\u0e16\u0e48\u0e32\u0e19\u0e2b\u0e34\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e4a\u0e32\u0e0b \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e21\u0e32\u0e13\u0e39\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e40\u0e0a\u0e48\u0e19\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u5efa\u8a2d 447\/61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034534\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e07\u0e44\u0e17\u0e48 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41002\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41002\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034534 \u0e1a\u0e08.\u0e15\u0e07\u0e44\u0e17\u0e48 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 41002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 447\/60  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0205569034879\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35\u0e18\u0e32\u0e23\u0e32 1589 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569034879 \u0e1a\u0e08.\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35\u0e18\u0e32\u0e23\u0e32 1589 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 68201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u4e0d\u52d5\u7523 141\/322  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19? \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0215569008789\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e35\u0e40\u0e27\u0e17\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"75000\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"75000\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569008789 \u0e1a\u0e08.\u0e27\u0e32\u0e23\u0e35\u0e40\u0e27\u0e17\u0e22\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 75000 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e15\u0e23\u0e27\u0e08\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22\u0e42\u0e23\u0e04 \u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14 \u0e09\u0e35\u0e14\u0e27\u0e31\u0e04\u0e0b\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 115  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0405569006245\",\"name_th\":\"\u0e1a\u0e08.\u0e2e\u0e48\u0e2d\u0e07\u0e01\u0e07\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0405569006245 \u0e1a\u0e08.\u0e2e\u0e48\u0e2d\u0e07\u0e01\u0e07\u0e42\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e31\u0e14\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e08\u0e31\u0e14\u0e41\u0e1e\u0e47\u0e01\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30 \u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 888\/122  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0573569001968\",\"name_th\":\"\u0e2b\u0e08.\u0e28\u0e28\u0e34\u0e1e\u0e34\u0e21\u0e25 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c  \u0e2d\u0e2d\u0e25\u0e25\u0e4c\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47213\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47213\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569001968 \u0e2b\u0e08.\u0e28\u0e28\u0e34\u0e1e\u0e34\u0e21\u0e25 \u0e42\u0e1b\u0e23\u0e14\u0e31\u0e01\u0e2a\u0e4c  \u0e2d\u0e2d\u0e25\u0e25\u0e4c 2569-07-01 100000 47213 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 56  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0655569002078\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e25\u0e31\u0e0f\u0e10\u0e4c343 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46421\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46421\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002078 \u0e1a\u0e08.\u0e1e\u0e25\u0e31\u0e0f\u0e10\u0e4c343 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 46421 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 97  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e0b\u0e2d\u0e22 1 \u0e16\u0e19\u0e19\u0e0a\u0e32\u0e15\u0e34\u0e15\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0715569002417\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1a\u0e35\u0e19 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10761\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10761\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0715569002417 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e1a\u0e35\u0e19 \u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 10761 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e32\u0e41\u0e1f\u0e0b\u0e2d\u0e07 \u88fd\u9020 61  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e1a\u0e38\u0e23\u0e35 \u30ab\u30fc\u30f3\u30c1\u30e3\u30ca\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0735569006676\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46441\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46441\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006676 \u0e1a\u0e08.\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 46441 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e0a\u0e48\u0e2d\u0e07\u0e1b\u0e32\u0e01\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 61\/1  \u0e16\u0e19\u0e19\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e27\u0e31\u0e07 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0905569005201\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":100000,\"capital_display\":\"100,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10752\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10752\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005201 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e2a \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 100000 10752 \u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e32\u0e27 \u0e2b\u0e27\u0e32\u0e19 \u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e0b\u0e2d\u0e2a\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a \u0e41\u0e22\u0e21 \u0e1c\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15(oem) \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 40  \u0e0b\u0e2d\u0e22 7\/1 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0105569129765\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35\u0e0b\u0e35 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":99000,\"capital_display\":\"99,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129765 \u0e1a\u0e08.\u0e2d\u0e32\u0e23\u0e4c\u0e0b\u0e35\u0e0b\u0e35 \u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 99000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 64\/77  \u0e0b\u0e2d\u0e22 \u0e17\u0e27\u0e35\u0e27\u0e31\u0e12\u0e19\u0e32 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0205569037843\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e0a\u0e19\u0e48\u0e32\u0e27\u0e35 \u0e2a\u0e15\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":90000,\"capital_display\":\"90,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0205569037843 \u0e1a\u0e08.\u0e44\u0e0a\u0e19\u0e48\u0e32\u0e27\u0e35 \u0e2a\u0e15\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 90000 85500 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e41\u0e19\u0e30\u0e41\u0e19\u0e27\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u6559\u80b2 123  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569127142\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e23\u0e22\u0e4c\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":80000,\"capital_display\":\"80,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"32501\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"32501\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127142 \u0e1a\u0e08.\u0e40\u0e23\u0e22\u0e4c\u0e40\u0e27\u0e35\u0e22\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 80000 32501 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1c\u0e25\u0e34\u0e15 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e17\u0e14\u0e2a\u0e2d\u0e1a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a \u0e2a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e40\u0e27\u0e0a\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e35 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e35 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u88fd\u9020 25  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 70 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0213569001359\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e0a \u0e2a\u0e04\u0e27\u0e34\u0e14\u0e14\u0e35\u0e49\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":50001,\"capital_display\":\"50,001 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47734\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47734\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0213569001359 \u0e2b\u0e08.\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e23\u0e34\u0e0a \u0e2a\u0e04\u0e27\u0e34\u0e14\u0e14\u0e35\u0e49 2569-07-23 50001 47734 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67\/1  \u0e16\u0e19\u0e19\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e04\u0e07\u0e04\u0e32 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569142605\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e1a\u0e25\u0e34\u0e04 \u0e2a\u0e42\u0e15\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47524\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47524\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142605 \u0e1a\u0e08.\u0e21\u0e32\u0e23\u0e4c\u0e1a\u0e25\u0e34\u0e04 \u0e2a\u0e42\u0e15\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 50000 47524 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d \u0e02\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 1788  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 3001-3003,3009-3014 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 30 \u0e16\u0e19\u0e19\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\u0e15\u0e31\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569023347\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e23\u0e32\u0e27\u0e34\u0e17\u0e32\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569023347 \u0e1a\u0e08.\u0e01\u0e23\u0e32\u0e27\u0e34\u0e17\u0e32\u0e2a \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25 \u0e41\u0e2d\u0e14\u0e44\u0e27\u0e0b\u0e2d\u0e23\u0e35\u0e48 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 50000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 168\/162  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0803569001086\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e18\u0e2d\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569001086 \u0e2b\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e18\u0e2d 2569-07-25 50000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1a\u0e47\u0e14\u0e40\u0e15\u0e25\u0e47\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e17\u0e33\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e19\u0e31\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 17\/4  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0103569007994\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e32\u0e23\u0e34 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007994 \u0e2b\u0e08.\u0e21\u0e32\u0e23\u0e34 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 2569-07-23 50000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2a\u0e15\u0e23\u0e35\u0e21\u0e21\u0e34\u0e48\u0e07 \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e19\u0e47\u0e15\u0e1f\u0e25\u0e34\u0e01\u0e0b\u0e4c (netflix) \u0e22\u0e39\u0e17\u0e39\u0e1b (youtube) \u0e2d\u0e49\u0e32\u0e22\u0e09\u0e35\u0e2d\u0e35\u0e49 (igiyi) \u0e27\u0e35\u0e17\u0e35\u0e27\u0e35 (wetv) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e41\u0e2d\u0e1b\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (e-commerce) (\u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 81\/748  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 79 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569024386\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e2d\u0e1a\u0e35 \u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e40\u0e25\u0e04\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569024386 \u0e1a\u0e08.\u0e1a\u0e35\u0e42\u0e2d\u0e1a\u0e35 \u0e44\u0e1f\u0e40\u0e1a\u0e2d\u0e23\u0e4c \u0e40\u0e17\u0e40\u0e25\u0e04\u0e2d\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 50000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e48\u0e2d\u0e23\u0e49\u0e2d\u0e22\u0e2a\u0e32\u0e22 \u0e17\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e40\u0e14\u0e34\u0e19\u0e2a\u0e32\u0e22\u0e40\u0e04\u0e40\u0e1a\u0e34\u0e49\u0e25 \u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e46 \u5efa\u8a2d 288  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0215569009734\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e2d\u0e0a\u0e42\u0e2d \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07\",\"province_ja\":\"\u30e9\u30e8\u30fc\u30f3\u770c\",\"search_text\":\"0215569009734 \u0e1a\u0e08.\u0e42\u0e2d\u0e40\u0e2d\u0e0a\u0e42\u0e2d \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 50000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 998\/214  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e23\u0e30\u0e22\u0e2d\u0e07 \u30e9\u30e8\u30fc\u30f3\u770c\"},{\"reg_no\":\"0275569001156\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e13\u0e32 \u0e40\u0e02\u0e15\u0e10\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27\",\"province_ja\":\"\u30b5\u30b1\u30fc\u30aa\u770c\",\"search_text\":\"0275569001156 \u0e1a\u0e08.\u0e2d\u0e13\u0e32 \u0e40\u0e02\u0e15\u0e10\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 50000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u60c5\u5831\u901a\u4fe1\u30fbit 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e23\u0e30\u0e41\u0e01\u0e49\u0e27 \u30b5\u30b1\u30fc\u30aa\u770c\"},{\"reg_no\":\"0325569001252\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"86101\",\"industry_category\":\"\u533b\u7642\u30fb\u798f\u7949\",\"industry_label\":\"86101\uff5c\u533b\u7642\u30fb\u798f\u7949\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0325569001252 \u0e1a\u0e08.\u0e44\u0e1a\u0e23\u0e17\u0e4c\u0e2a\u0e44\u0e21\u0e25\u0e4c \u0e40\u0e14\u0e19\u0e17\u0e31\u0e25\u0e41\u0e04\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 50000 86101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e2d\u0e01\u0e0a\u0e19  \u0e2a\u0e16\u0e32\u0e19\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25  \u0e23\u0e31\u0e1a\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e40\u0e08\u0e47\u0e1a  \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e23\u0e21\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c  \u0e01\u0e32\u0e23\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u533b\u7642\u30fb\u798f\u7949 391\/2  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e02\u0e27\u0e32\u0e27 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e16\u0e19\u0e19\u0e27\u0e35\u0e23\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0105569136885\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e25\u0e41\u0e1f\u0e19\u0e15\u0e4c \u0e04\u0e34\u0e07 \u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136885 \u0e1a\u0e08.\u0e2d\u0e35\u0e40\u0e25\u0e41\u0e1f\u0e19\u0e15\u0e4c \u0e04\u0e34\u0e07 \u0e1a\u0e47\u0e2d\u0e01\u0e0b\u0e34\u0e48\u0e07  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 50000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e2d\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e35\u0e2c\u0e32\u0e21\u0e27\u0e22\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b (\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27) \u6559\u80b2 81  \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0135569022197\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e34\u0e16\u0e35\u0e19\u0e27\u0e31\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"72109\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"72109\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569022197 \u0e1a\u0e08.\u0e27\u0e34\u0e16\u0e35\u0e19\u0e27\u0e31\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 50000 72109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e1c\u0e25\u0e34\u0e15 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1a\u0e2d\u0e23\u0e4c\u0e14\u0e44\u0e21\u0e42\u0e04\u0e23\u0e04\u0e2d\u0e19\u0e42\u0e17\u0e23\u0e25\u0e40\u0e25\u0e2d\u0e23\u0e4c \u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e0a\u0e38\u0e14\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 98\/70  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e1f-\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e07\u0e2a\u0e34\u0e15-\u0e19\u0e04\u0e23\u0e19\u0e32\u0e22\u0e01 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569135331\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e2e\u0e40\u0e14\u0e19\u0e17\u0e34\u0e04 \u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569135331 \u0e1a\u0e08.\u0e44\u0e2e\u0e40\u0e14\u0e19\u0e17\u0e34\u0e04 \u0e41\u0e1a\u0e07\u0e04\u0e2d\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-17 50000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 334  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e2a\u0e2d\u0e07 30 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e2a\u0e2d\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0505569016096\",\"name_th\":\"\u0e1a\u0e08.\u0e0a\u0e49\u0e32\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-16\",\"reg_date_sort\":25690716,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016096 \u0e1a\u0e08.\u0e0a\u0e49\u0e32\u0e07 \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e1e\u0e23\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-16 50000 46109 \u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e43\u0e0a\u0e49\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07  \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28.2545 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16\/40  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0123569002160\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e1a\u0e2d\u0e21\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46443\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46443\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002160 \u0e2b\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e1a\u0e2d\u0e21 2569-07-14 50000 46443 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 8\/159\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0505569015863\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e2a\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015863 \u0e1a\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e04\u0e2d\u0e21\u0e1e\u0e32\u0e2a\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 50000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e1e\u0e47\u0e04\u0e40\u0e01\u0e08\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 166\/69  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 12\/4 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0835569012985\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e30\u0e04\u0e32\u0e2a\u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012985 \u0e1a\u0e08.\u0e2d\u0e30\u0e04\u0e32\u0e2a\u0e41\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 50000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e15\u0e32\u0e21\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e32\u0e25\u0e33 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e19\u0e17\u0e34\u0e27\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e42\u0e21\u0e2a\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e1a\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 3\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0573569002182\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e23 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"25112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"25112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\",\"search_text\":\"0573569002182 \u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e23 \u0e21\u0e31\u0e48\u0e07\u0e21\u0e35 \u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02 2569-07-13 50000 25112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e34\u0e15 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a \u0e42\u0e23\u0e07\u0e0a\u0e38\u0e1a \u0e42\u0e23\u0e07\u0e1e\u0e48\u0e19\u0e2a\u0e35 \u0e41\u0e25\u0e30\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e01\u0e23\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e15\u0e39 \u0e01\u0e23\u0e2d\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e43\u0e2b\u0e0d\u0e48 (gate)  \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e21\u0e49\u0e27\u0e19 \u0e1b\u0e23\u0e30\u0e15\u0e39\u0e22\u0e37\u0e14 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e21\u0e38\u0e49\u0e07\u0e25\u0e27\u0e14 \u0e42\u0e04\u0e23\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32 \u0e23\u0e32\u0e27\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e23\u0e31\u0e49\u0e27 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e25\u0e49\u0e32\u0e22\u0e01\u0e31\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e17\u0e35\u0e48\u0e17\u0e33\u0e08\u0e32\u0e01\u0e42\u0e25\u0e2b\u0e30 \u0e40\u0e2b\u0e25\u0e47\u0e01 \u0e2a\u0e41\u0e15\u0e19\u0e40\u0e25\u0e2a \u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21  \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e25\u0e2b\u0e30\u0e1c\u0e2a\u0e21\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u88fd\u9020 330  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22 \u30c1\u30a2\u30f3\u30e9\u30fc\u30a4\u770c\"},{\"reg_no\":\"0105569130879\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e31\u0e07 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569130879 \u0e1a\u0e08.\u0e22\u0e31\u0e07 \u0e04\u0e34\u0e14\u0e2a\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 50000 74101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 928  \u0e0b\u0e2d\u0e22 \u0e40\u0e17\u0e2d\u0e14\u0e44\u0e17 21 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e2d\u0e14\u0e44\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131212\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e40\u0e15\u0e35\u0e22\u0e19 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131212 \u0e1a\u0e08.\u0e17\u0e48\u0e32\u0e40\u0e15\u0e35\u0e22\u0e19 (2026) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 50000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u5bbf\u6cca\u30fb\u98f2\u98df 130-132  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2a\u0e34\u0e19\u0e18\u0e23 \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c 1 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131697\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e14\u0e2d\u0e01\u0e1e\u0e38\u0e14 \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56299\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56299\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131697 \u0e1a\u0e08.\u0e1a\u0e49\u0e32\u0e19\u0e14\u0e2d\u0e01\u0e1e\u0e38\u0e14 \u0e1f\u0e39\u0e49\u0e14 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 50000 56299 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07 (snack box) \u0e0a\u0e38\u0e14\u0e02\u0e19\u0e21\u0e21\u0e07\u0e04\u0e25 \u0e40\u0e0b\u0e15\u0e02\u0e19\u0e21\u0e44\u0e17\u0e22\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e48\u0e07 \u0e0a\u0e38\u0e14\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e27\u0e48\u0e32\u0e07\u0e43\u0e19\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e17\u0e28\u0e01\u0e32\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u5bbf\u6cca\u30fb\u98f2\u98df 85  \u0e0b\u0e2d\u0e22 \u0e1e\u0e34\u0e1a\u0e39\u0e25\u0e2d\u0e38\u0e1b\u0e16\u0e31\u0e21\u0e16\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0243569000662\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32\",\"province_ja\":\"\u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\",\"search_text\":\"0243569000662 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e2d\u0e2a\u0e27\u0e35\u0e17\u0e35 \u0e04\u0e2d\u0e19\u0e2a\u0e15\u0e23\u0e31\u0e04\u0e0a\u0e31\u0e48\u0e19 2569-07-10 50000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07  \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e15\u0e48\u0e2d\u0e40\u0e15\u0e34\u0e21 \u0e23\u0e37\u0e49\u0e2d\u0e16\u0e2d\u0e19 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e34\u0e48\u0e07\u0e1b\u0e25\u0e39\u0e01\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5efa\u8a2d 28  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e09\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e40\u0e17\u0e23\u0e32 \u30c1\u30e3\u30c1\u30e5\u30fc\u30f3\u30b5\u30aa\u770c\"},{\"reg_no\":\"0103569007277\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e27\u0e35\u0e17\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e40\u0e14\u0e0b\u0e35\u0e48\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569007277 \u0e2b\u0e08.\u0e2a\u0e27\u0e35\u0e17\u0e40\u0e2e\u0e32\u0e2a\u0e4c \u0e40\u0e14\u0e0b\u0e35\u0e48 2569-07-09 50000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e02\u0e32\u0e22\u0e1b\u0e25\u0e35\u0e01 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07 \u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32 \u0e02\u0e32\u0e22\u0e44\u0e1b \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e42\u0e14\u0e22\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e15\u0e23\u0e07   \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e49\u0e32\u0e19\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e2b\u0e21\u0e27\u0e01 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a \u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 500  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 \u0e21.\u0e1e\u0e38\u0e14\u0e15\u0e32\u0e19 \u0e16\u0e19\u0e19\u0e21\u0e32\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129781\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e32\u0e21\u0e48\u0e32 \u0e23\u0e39\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10619\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10619\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129781 \u0e1a\u0e08.\u0e2d\u0e32\u0e21\u0e48\u0e32 \u0e23\u0e39\u0e17\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 50000 10619 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e02\u0e49\u0e32\u0e27 \u0e02\u0e49\u0e32\u0e27\u0e42\u0e1e\u0e14 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07 \u0e21\u0e31\u0e19\u0e2a\u0e33\u0e1b\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e2d\u0e31\u0e14\u0e40\u0e21\u0e47\u0e14 \u0e01\u0e32\u0e41\u0e1f \u0e40\u0e21\u0e47\u0e14\u0e21\u0e30\u0e21\u0e48\u0e27\u0e07\u0e2b\u0e34\u0e21\u0e1e\u0e32\u0e19\u0e15\u0e4c \u0e16\u0e31\u0e48\u0e27 \u0e07\u0e32 \u0e25\u0e30\u0e2b\u0e38\u0e48\u0e07 \u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19 \u0e1b\u0e2d \u0e1d\u0e49\u0e32\u0e22 \u0e19\u0e38\u0e48\u0e19 \u0e1e\u0e37\u0e0a\u0e44\u0e23\u0e48 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e04\u0e23\u0e31\u0e48\u0e07 \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e40\u0e02\u0e32\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e44\u0e21\u0e49 \u0e41\u0e23\u0e48 \u0e22\u0e32\u0e07 \u0e22\u0e32\u0e07\u0e14\u0e34\u0e1a \u0e22\u0e32\u0e07\u0e41\u0e1c\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e32\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e37\u0e48\u0e19\u0e2d\u0e31\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e21\u0e32\u0e08\u0e32\u0e01 \u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e14\u0e02\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32 \u0e02\u0e2d\u0e07\u0e1b\u0e48\u0e32\u0e2a\u0e21\u0e38\u0e19\u0e44\u0e1e\u0e23\u0e41\u0e25\u0e30\u0e1e\u0e37\u0e0a\u0e1c\u0e25\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 309\/136  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e2a\u0e17\u0e32\u0e23\u0e48\u0e32 \u0e40\u0e2e\u0e40\u0e27\u0e48\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 20 \u0e0b\u0e2d\u0e22 \u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a 17 \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e2d\u0e19\u0e19\u0e38\u0e0a \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0503569004517\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e32\u0e22\u0e04\u0e25\u0e35\u0e19 \u0e42\u0e1b\u0e23\u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004517 \u0e2b\u0e08.\u0e1a\u0e32\u0e22\u0e04\u0e25\u0e35\u0e19 \u0e42\u0e1b\u0e23\u0e04\u0e25\u0e35\u0e19\u0e19\u0e34\u0e48\u0e07 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 2569-07-09 50000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e41\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 \u0e2d\u0e1e\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e19\u0e17\u0e4c \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e10\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 299\/25  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0803569000926\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d.\u0e40\u0e2d\u0e1f.\u0e40\u0e2d\u0e1f \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\",\"search_text\":\"0803569000926 \u0e2b\u0e08.\u0e40\u0e2d.\u0e40\u0e2d\u0e1f.\u0e40\u0e2d\u0e1f \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e 2569-07-09 50000 71209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e08\u0e31\u0e01\u0e23\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 152  \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19 \u0e08.\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a \u30ca\u30b3\u30fc\u30f3\u30b7\u30fc\u30bf\u30f3\u30de\u30e9\u30fc\u30c8\u770c\"},{\"reg_no\":\"0105569129145\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e08\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129145 \u0e1a\u0e08.\u0e41\u0e2d\u0e25\u0e08\u0e35\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 50000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e23\u0e31\u0e1a\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21 \u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e04\u0e49\u0e14 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e49\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c \u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 99\/6  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e19\u0e31\u0e19\u0e17\u0e27\u0e31\u0e19 \u0e1b\u0e34\u0e48\u0e19\u0e40\u0e01\u0e25\u0e49\u0e32-\u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32 \u0e16\u0e19\u0e19\u0e2d\u0e31\u0e28\u0e27\u0e1e\u0e34\u0e40\u0e0a\u0e29\u0e10\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569129242\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e27\u0e31\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62012\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62012\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129242 \u0e1a\u0e08.\u0e40\u0e2d\u0e44\u0e2d\u0e27\u0e31\u0e19 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 50000 62012 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e40\u0e2d\u0e40\u0e08\u0e19\u0e15\u0e4c\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e41\u0e25\u0e30\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c (licensing) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a saas \u60c5\u5831\u901a\u4fe1\u30fbit 75  \u0e0b\u0e2d\u0e22 \u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 38 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0323569000548\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e19\u0e32\u0e22\u0e2d\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c\",\"province_ja\":\"\u30b9\u30ea\u30f3\u770c\",\"search_text\":\"0323569000548 \u0e2b\u0e08.\u0e40\u0e2d\u0e2a\u0e40\u0e04 \u0e19\u0e32\u0e22\u0e2d\u0e14 2569-07-08 50000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 257  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e01\u0e23\u0e30\u0e27\u0e31\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2a\u0e38\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u30b9\u30ea\u30f3\u770c\"},{\"reg_no\":\"0105569127771\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e07\u0e19\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569127771 \u0e1a\u0e08.\u0e27\u0e48\u0e32\u0e07\u0e19\u0e32\u0e27 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 50000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07 \u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19 \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e19\u0e31\u0e14\u0e2b\u0e21\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e43\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e21\u0e34\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01 \u60c5\u5831\u901a\u4fe1\u30fbit 92  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e47\u0e19\u0e17\u0e23\u0e31\u0e25\u0e1e\u0e32\u0e23\u0e4c\u0e04\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28\u0e40\u0e0b\u0e2a  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 92 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 35 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e214 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0503569004444\",\"name_th\":\"\u0e2b\u0e08.\u0e25\u0e32\u0e22\u0e44\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e07\u0e34\u0e19\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0503569004444 \u0e2b\u0e08.\u0e25\u0e32\u0e22\u0e44\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e07\u0e34\u0e19 2569-07-07 50000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 16  \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e27\u0e31\u0e27\u0e25\u0e32\u0e22 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0733569000994\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e1b\u0e25\u0e32\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47212\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47212\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569000994 \u0e2b\u0e08.\u0e17\u0e35\u0e40\u0e2d\u0e47\u0e19\u0e40\u0e04 \u0e1b\u0e25\u0e32\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 2569-07-07 50000 47212 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e49\u0e32 \u0e1b\u0e25\u0e32\u0e19\u0e49\u0e33\u0e08\u0e37\u0e14 \u0e1b\u0e25\u0e32\u0e19\u0e49\u0e33\u0e40\u0e04\u0e47\u0e21 \u0e1b\u0e25\u0e32\u0e17\u0e30\u0e40\u0e25 \u0e1b\u0e25\u0e32\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e1e\u0e23\u0e23\u0e13\u0e44\u0e21\u0e49\u0e19\u0e49\u0e33 \u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e23\u0e07 \u0e15\u0e39\u0e49 \u0e1b\u0e25\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e1b\u0e25\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e15\u0e39\u0e49\u0e1b\u0e25\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e21 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e42\u0e23\u0e04\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e21\u0e35\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e19\u0e49\u0e33 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01 \u0e04\u0e49\u0e32\u0e2a\u0e48\u0e07 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e22\u0e31\u0e07\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30 \u0e17\u0e32\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 67\/7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0403569002922\",\"name_th\":\"\u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e28\u0e34\u0e23\u0e34 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81293\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81293\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\",\"province_ja\":\"\u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\",\"search_text\":\"0403569002922 \u0e2b\u0e08.\u0e1b\u0e23\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e10\u0e28\u0e34\u0e23\u0e34 \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-04 50000 81293 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e09\u0e35\u0e14\u0e1e\u0e48\u0e19 \u0e01\u0e33\u0e08\u0e31\u0e14 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e1b\u0e25\u0e27\u0e01 \u0e21\u0e2d\u0e14 \u0e41\u0e21\u0e25\u0e07 \u0e2b\u0e19\u0e39\u0e01\u0e33\u0e08\u0e31\u0e14\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e1e\u0e32\u0e2b\u0e30\u0e19\u0e33\u0e42\u0e23\u0e04 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07\u0e23\u0e1a\u0e01\u0e27\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 439\/3  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e14\u0e2d\u0e30\u0e44\u0e1a\u0e23\u0e17\u0e4c \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u30b3\u30fc\u30f3\u30b1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0445569001588\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21\",\"province_ja\":\"\u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\",\"search_text\":\"0445569001588 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e1e\u0e25\u0e31\u0e2a \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 50000 43210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u5efa\u8a2d 8  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21 \u30de\u30cf\u30fc\u30b5\u30fc\u30e9\u30ab\u30fc\u30e0\u770c\"},{\"reg_no\":\"0835569012390\",\"name_th\":\"\u0e1a\u0e08.\u0e19\u0e32\u0e1b\u0e32 \u0e41\u0e2d\u0e42\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012390 \u0e1a\u0e08.\u0e19\u0e32\u0e1b\u0e32 \u0e41\u0e2d\u0e42\u0e23 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 50000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e15\u0e32\u0e21\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48 \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e2b\u0e21\u0e32\u0e25\u0e33 \u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e19\u0e17\u0e34\u0e27\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c  \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e39\u0e49\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e42\u0e21\u0e2a\u0e23 \u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e1a\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2b\u0e22\u0e48\u0e2d\u0e19\u0e43\u0e08 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u904b\u8f38\u30fb\u7269\u6d41 78\/395  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569006467\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e1e\u0e25 \u0e04\u0e25\u0e31\u0e1a\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006467 \u0e2b\u0e08.\u0e40\u0e14\u0e2d\u0e30 \u0e42\u0e1e\u0e25 \u0e04\u0e25\u0e31\u0e1a 2569-07-01 50000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e01\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e40\u0e0a\u0e48\u0e19 \u0e1f\u0e34\u0e15\u0e40\u0e19\u0e2a \u0e40\u0e0b\u0e47\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c, \u0e22\u0e34\u0e21, \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\u0e42\u0e22\u0e04\u0e30, \u0e1e\u0e34\u0e25\u0e32\u0e17\u0e34\u0e2a, \u0e21\u0e27\u0e22\u0e44\u0e17\u0e22, \u0e04\u0e32\u0e23\u0e4c\u0e14\u0e34\u0e42\u0e2d) \u6559\u80b2 9\/46  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e25 5 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0505569014786\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e1a\u0e31\u0e19\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014786 \u0e1a\u0e08.\u0e2d\u0e1a\u0e31\u0e19\u0e41\u0e14\u0e19\u0e0b\u0e4c \u0e1e\u0e25\u0e31\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 50000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a.\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e1e.\u0e28. 2545 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 161\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0745569006943\",\"name_th\":\"\u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e23\u0e19\u0e08\u0e4c \u0e40\u0e27\u0e22\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\",\"search_text\":\"0745569006943 \u0e1a\u0e08.\u0e2a\u0e40\u0e15\u0e23\u0e19\u0e08\u0e4c \u0e40\u0e27\u0e22\u0e4c \u0e40\u0e2d\u0e47\u0e01\u0e0b\u0e4c\u0e1e\u0e25\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 50000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e19\u0e4d\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 99\/66  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e2a\u0e32\u0e04\u0e23 \u30b5\u30e0\u30c3\u30c8\u30b5\u30fc\u30b3\u30fc\u30f3\u770c\"},{\"reg_no\":\"0945569000668\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33 \u0e40\u0e2d\u0e2a\u0e2d\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":50000,\"capital_display\":\"50,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74902\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74902\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000668 \u0e1a\u0e08.\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33 \u0e40\u0e2d\u0e2a\u0e2d\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 50000 74902 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e01\u0e48\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 49  \u0e16\u0e19\u0e19\u0e16\u0e19\u0e19\u0e2a\u0e24\u0e29\u0e14\u0e34\u0e4c \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0603569001452\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e0b\u0e35\u0e14\u0e35\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":40000,\"capital_display\":\"40,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47595\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47595\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001452 \u0e2b\u0e08.\u0e1a\u0e35\u0e1a\u0e35\u0e0b\u0e35\u0e14\u0e35 2569-07-02 40000 47595 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 44\/1  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0835569013124\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e01\u0e21\u0e1a\u0e34\u0e15 \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-15\",\"reg_date_sort\":25690715,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569013124 \u0e1a\u0e08.\u0e41\u0e01\u0e21\u0e1a\u0e34\u0e15 \u0e25\u0e35\u0e40\u0e01\u0e34\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-15 30000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 49\/797  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0113569002453\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e23\u0e31\u0e13\u0e22\u0e32  \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"78109\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"78109\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002453 \u0e2b\u0e08.\u0e0a\u0e23\u0e31\u0e13\u0e22\u0e32  \u0e42\u0e01\u0e25\u0e1a\u0e2d\u0e25\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a 2569-07-14 30000 78109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e08\u0e49\u0e32\u0e07\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07\u0e14\u0e49\u0e32\u0e27\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 7  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 \u0e27\u0e31\u0e14\u0e1a\u0e32\u0e07\u0e1d\u0e49\u0e32\u0e22 \u0e16\u0e19\u0e19\u0e1b\u0e39\u0e48\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e21\u0e34\u0e07\u0e1e\u0e23\u0e32\u0e22 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569131239\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"64202\",\"industry_category\":\"\u91d1\u878d\u30fb\u4fdd\u967a\",\"industry_label\":\"64202\uff5c\u91d1\u878d\u30fb\u4fdd\u967a\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131239 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e2d\u0e47\u0e21\u0e40\u0e04 \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 30000 64202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e16\u0e37\u0e2d\u0e2b\u0e38\u0e49\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e43\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e27\u0e31\u0e07\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e40\u0e07\u0e34\u0e19\u0e1b\u0e31\u0e19\u0e1c\u0e25 \u0e14\u0e2d\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2d\u0e31\u0e19\u0e0a\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u91d1\u878d\u30fb\u4fdd\u967a 136  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e21\u0e17\u0e35\u0e482 \u0e0b\u0e2d\u0e22 54 \u0e41\u0e22\u0e01 4 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0775569002930\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e04\u0e25\u0e35\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c\",\"province_ja\":\"\u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\",\"search_text\":\"0775569002930 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e04\u0e25\u0e35\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 30000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 \u0e23\u0e31\u0e1a\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e2d\u0e32\u0e14\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 432\/82  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e34\u0e15\u0e23\u0e44\u0e21\u0e15\u0e23\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 \u0e2d\u0e33\u0e19\u0e27\u0e22\u0e1c\u0e25 \u0e16\u0e19\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e21\u0e07\u0e04\u0e25 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u30d7\u30e9\u30c1\u30e5\u30ef\u30c3\u30d7\u30ad\u30fc\u30ea\u30fc\u30ab\u30f3\u770c\"},{\"reg_no\":\"0313569001021\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e23\u0e35 \u0e04\u0e25\u0e35\u0e19\u0e42\u0e1b\u0e23\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"81210\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"81210\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c\",\"province_ja\":\"\u30d6\u30ea\u30fc\u30e9\u30e0\u770c\",\"search_text\":\"0313569001021 \u0e2b\u0e08.\u0e1a\u0e38\u0e23\u0e35 \u0e04\u0e25\u0e35\u0e19\u0e42\u0e1b\u0e23 2569-07-09 30000 81210 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 160\/17  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 19 \u0e08.\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e31\u0e21\u0e22\u0e4c \u30d6\u30ea\u30fc\u30e9\u30e0\u770c\"},{\"reg_no\":\"0505569015022\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e01\u0e0b\u0e31\u0e2a \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"55101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"55101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015022 \u0e1a\u0e08.\u0e40\u0e19\u0e01\u0e0b\u0e31\u0e2a \u0e2e\u0e2d\u0e2a\u0e1e\u0e34\u0e17\u0e32\u0e25\u0e34\u0e15\u0e35\u0e49 \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e19\u0e15\u0e4c  \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 30000 55101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21  \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23  \u0e1a\u0e32\u0e23\u0e4c  \u0e44\u0e19\u0e17\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 116\/199  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 12 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0123569002062\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e43\u0e2b\u0e0d\u0e48 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 (2026)\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002062 \u0e2b\u0e08.\u0e1a\u0e38\u0e0d\u0e43\u0e2b\u0e0d\u0e48 \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 (2026) 2569-07-01 30000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 5\/1422  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e0b\u0e2d\u0e22 9 \u0e16\u0e19\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020364\",\"name_th\":\"\u0e1a\u0e08.\u0e01\u0e4b\u0e32\u0e27\u0e15\u0e34\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":30000,\"capital_display\":\"30,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020364 \u0e1a\u0e08.\u0e01\u0e4b\u0e32\u0e27\u0e15\u0e34\u0e48\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 30000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e25\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e48\u0e21 \u0e42\u0e21\u0e40\u0e14\u0e25 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e41\u0e1a\u0e1a\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 38\/156  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569141277\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-26\",\"reg_date_sort\":25690726,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569141277 \u0e1a\u0e08.\u0e22\u0e31\u0e27\u0e23\u0e4c \u0e1a\u0e31\u0e14\u0e14\u0e35\u0e49 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-26 20000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e15\u0e25\u0e32\u0e14\u0e01\u0e25\u0e32\u0e07\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e0a\u0e48\u0e19 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25 (buddy) \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e20\u0e32\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e34\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 468  \u0e0b\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e2833\u0e41\u0e22\u0e014 \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0675569001551\",\"name_th\":\"\u0e1a\u0e08.\u0e18\u0e19\u0e32 1981 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\",\"search_text\":\"0675569001551 \u0e1a\u0e08.\u0e18\u0e19\u0e32 1981 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-23 20000 63113 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u60c5\u5831\u901a\u4fe1\u30fbit 145  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e48\u0e32\u0e44\u0e2e\u0e2b\u0e22\u0e48\u0e2d\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e4c \u30da\u30c3\u30c1\u30e3\u30d6\u30fc\u30f3\u770c\"},{\"reg_no\":\"0395569000469\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e2a\u0e41\u0e15\u0e47\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62011\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62011\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39\",\"province_ja\":\"\u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\",\"search_text\":\"0395569000469 \u0e1a\u0e08.\u0e40\u0e2d\u0e40\u0e25\u0e35\u0e22\u0e19 \u0e2a\u0e41\u0e15\u0e47\u0e01\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 20000 62011 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e40\u0e27\u0e47\u0e1a\u0e41\u0e2d\u0e1b\u0e1e\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u60c5\u5831\u901a\u4fe1\u30fbit 97  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e08.\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e25\u0e33\u0e20\u0e39 \u30ce\u30fc\u30f3\u30d6\u30ef\u30e9\u30e0\u30d7\u30fc\u770c\"},{\"reg_no\":\"0603569001631\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e2b\u0e01\u0e40\u0e01\u0e49\u0e32\",\"reg_date\":\"2569-07-17\",\"reg_date_sort\":25690717,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"52292\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"52292\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\",\"search_text\":\"0603569001631 \u0e2b\u0e08.\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e2b\u0e01\u0e40\u0e01\u0e49\u0e32 2569-07-17 20000 52292 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 70\/5  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e19\u0e04\u0e23\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e4c \u30ca\u30b3\u30fc\u30f3\u30b5\u30ef\u30f3\u770c\"},{\"reg_no\":\"0485569000905\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e19\u0e34\u0e22\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-13\",\"reg_date_sort\":25690713,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63120\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63120\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0485569000905 \u0e1a\u0e08.\u0e25\u0e32\u0e19\u0e19\u0e34\u0e22\u0e32\u0e22 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-13 20000 63120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e48\u0e32\u0e19\u0e19\u0e27\u0e19\u0e34\u0e22\u0e32\u0e22 \u0e27\u0e23\u0e23\u0e13\u0e01\u0e23\u0e23\u0e21 \u0e1a\u0e17\u0e1b\u0e23\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e40\u0e02\u0e35\u0e22\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e02\u0e36\u0e49\u0e19\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e08\u0e32\u0e01\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-book\/e-content) \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e30\u0e41\u0e19\u0e19\u0e2a\u0e30\u0e2a\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e41\u0e1a\u0e48\u0e07\u0e1b\u0e31\u0e19\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e19\u0e31\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e31\u0e01\u0e41\u0e1b\u0e25\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19 \u60c5\u5831\u901a\u4fe1\u30fbit 29\/1  \u0e16\u0e19\u0e19\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e19\u0e04\u0e23 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0303569002664\",\"name_th\":\"\u0e2b\u0e08.\u0e0a\u0e47\u0e2d\u0e1b \u0e0a\u0e47\u0e2d\u0e1b 1998\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002664 \u0e2b\u0e08.\u0e0a\u0e47\u0e2d\u0e1b \u0e0a\u0e47\u0e2d\u0e1b 1998 2569-07-09 20000 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 152\/293  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 0 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0613569000171\",\"name_th\":\"\u0e2b\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0613569000171 \u0e2b\u0e08.\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 2569-07-09 20000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e04\u0e33\u0e2d\u0e23\u0e23\u0e16\u0e32\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e27\u0e48\u0e32\u0e04\u0e27\u0e32\u0e21 \u0e41\u0e01\u0e49\u0e15\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e2d\u0e23\u0e23\u0e16\u0e04\u0e14\u0e35\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e28\u0e32\u0e25\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e42\u0e15\u0e15\u0e38\u0e25\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10\u0e17\u0e38\u0e01\u0e41\u0e2b\u0e48\u0e07 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 86  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e2d\u0e38\u0e17\u0e31\u0e22\u0e18\u0e32\u0e19\u0e35 \u30a6\u30bf\u30a4\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569129234\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e35\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56103\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56103\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569129234 \u0e1a\u0e08.\u0e40\u0e08\u0e40\u0e2d\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e2d\u0e35\u0e40\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 20000 56103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e23\u0e49\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48 \u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e02\u0e19\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 77\/169  \u0e0b\u0e2d\u0e22 \u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35 68 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0165569001483\",\"name_th\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e01\u0e34\u0e49\u0e19 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"82990\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"82990\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ed\u30c3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0165569001483 \u0e1a\u0e08.\u0e22\u0e39\u0e01\u0e34\u0e49\u0e19 \u0e40\u0e2d\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 20000 82990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07  \u0e15\u0e32\u0e21\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14  \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25  \u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e23\u0e31\u0e10 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 41\/40  \u0e0b\u0e2d\u0e22 \u0e21.\u0e40\u0e25\u0e04\u0e1a\u0e38\u0e29\u0e1a\u0e32 \u0e08.\u0e25\u0e1e\u0e1a\u0e38\u0e23\u0e35 \u30ed\u30c3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0523569001321\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e32\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"10619\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"10619\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001321 \u0e2b\u0e08.\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e32\u0e14\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e32\u0e21\u0e31\u0e04\u0e04\u0e35 2569-07-03 20000 10619 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e04\u0e31\u0e14\u0e40\u0e01\u0e23\u0e14 \u0e41\u0e1b\u0e23\u0e23\u0e39\u0e1b \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 3  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0113569002194\",\"name_th\":\"\u0e2b\u0e08.\u0e15\u0e2d\u0e07\u0e08\u0e23\u0e23\u0e22\u0e4c\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47190\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47190\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0113569002194 \u0e2b\u0e08.\u0e15\u0e2d\u0e07\u0e08\u0e23\u0e23\u0e22\u0e4c 2569-07-02 20000 47190 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e01\u0e31\u0e4a\u0e01\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e41\u0e2a\u0e07 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e0a\u0e47\u0e2d\u0e1b\u0e0a\u0e48\u0e32\u0e07 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e17\u0e33\u0e07\u0e32\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 929\/336  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e34\u0e25\u0e25\u0e32\u0e08\u0e08\u0e34\u0e42\u0e2d \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c-\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0523569001313\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35.\u0e18\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":20000,\"capital_display\":\"20,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49339\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49339\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07\",\"province_ja\":\"\u30e9\u30e0\u30d1\u30fc\u30f3\u770c\",\"search_text\":\"0523569001313 \u0e2b\u0e08.\u0e17\u0e35.\u0e18\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-01 20000 49339 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e1d\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (logistics distribution) \u904b\u8f38\u30fb\u7269\u6d41 22  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e25\u0e33\u0e1b\u0e32\u0e07 \u30e9\u30e0\u30d1\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569142346\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e27\u0e1a\u0e4c\u0e2a \u0e2d\u0e31\u0e19\u0e25\u0e34\u0e21\u0e34\u0e15 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":18000,\"capital_display\":\"18,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142346 \u0e1a\u0e08.\u0e44\u0e27\u0e1a\u0e4c\u0e2a \u0e2d\u0e31\u0e19\u0e25\u0e34\u0e21\u0e34\u0e15 (\u0e44\u0e17\u0e22\u0e41\u0e25\u0e19\u0e14\u0e4c) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 18000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e31\u0e19\u0e40\u0e17\u0e34\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e0a\u0e48\u0e19 \u0e08\u0e31\u0e14\u0e04\u0e2d\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e15 \u0e25\u0e30\u0e04\u0e23\u0e40\u0e27\u0e17\u0e35 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e15\u0e48\u0e32\u0e07\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 33  \u0e0b\u0e2d\u0e22 \u0e2d\u0e34\u0e19\u0e17\u0e32\u0e21\u0e23\u0e30 17 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e19\u0e34\u0e08\u0e09\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0203569002703\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e35\u0e44\u0e2d\u0e1e\u0e35 \u0e08\u0e4a\u0e2d\u0e1a\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":18000,\"capital_display\":\"18,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49321\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49321\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002703 \u0e2b\u0e08.\u0e27\u0e35\u0e44\u0e2d\u0e1e\u0e35 \u0e08\u0e4a\u0e2d\u0e1a 2569-07-01 18000 49321 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e1e\u0e32\u0e2b\u0e19\u0e30 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01 \u0e2a\u0e16\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e17\u0e31\u0e48\u0e27\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23 \u904b\u8f38\u30fb\u7269\u6d41 213\/730  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e2d\u0e32\u0e17\u0e23\u0e44\u0e23\u0e48\u0e01\u0e25\u0e49\u0e27\u0e22 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e0b\u0e2d\u0e22 24 \u0e16\u0e19\u0e19\u0e44\u0e23\u0e48\u0e01\u0e25\u0e49\u0e27\u0e22 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0115569022979\",\"name_th\":\"\u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":15000,\"capital_display\":\"15,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71102\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71102\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569022979 \u0e1a\u0e08.\u0e44\u0e1e\u0e23\u0e21\u0e4c \u0e2a\u0e15\u0e23\u0e31\u0e04\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 15000 71102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e02\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e20\u0e32\u0e1e\u0e2a\u0e32\u0e21\u0e21\u0e34\u0e15\u0e34 (3d) \u0e20\u0e32\u0e1e\u0e2a\u0e2d\u0e07\u0e21\u0e34\u0e15\u0e34 (2d) \u0e41\u0e2d\u0e19\u0e34\u0e40\u0e21\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e31\u0e28\u0e19\u0e35\u0e22\u0e20\u0e32\u0e1e\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e08\u0e32\u0e01\u0e2a\u0e20\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e) \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 607\/31  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 17 \u0e0b\u0e2d\u0e22 1 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e32\u0e23\u0e31\u0e01\u0e29\u0e3a \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0123569002089\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a\u0e0b\u0e2d\u0e23\u0e35\u0e48\u0e2a\u0e4c\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":15000,\"capital_display\":\"15,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"45302\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"45302\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0123569002089 \u0e2b\u0e08.\u0e17\u0e35\u0e0b\u0e35\u0e0b\u0e35 \u0e2d\u0e2d\u0e42\u0e15\u0e49 \u0e41\u0e2d\u0e04\u0e40\u0e0b\u0e2a\u0e0b\u0e2d\u0e23\u0e35\u0e48\u0e2a\u0e4c 2569-07-02 15000 45302 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 39\/39  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e2a\u0e35\u0e48\u0e44\u0e0a\u0e22\u0e17\u0e2d\u0e07 27\/1 \u0e16\u0e19\u0e19\u0e41\u0e08\u0e49\u0e07\u0e27\u0e31\u0e12\u0e19\u0e30 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0363569000882\",\"name_th\":\"\u0e2b\u0e08.\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e49\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e25\u0e32\u0e14 \u0e2b\u0e21\u0e39\u0e48 3\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":12000,\"capital_display\":\"12,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"01140\",\"industry_category\":\"\u8fb2\u6797\u6c34\u7523\",\"industry_label\":\"01140\uff5c\u8fb2\u6797\u6c34\u7523\",\"province_th\":\"\u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34\",\"province_ja\":\"\u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\",\"search_text\":\"0363569000882 \u0e2b\u0e08.\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e49\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e15\u0e25\u0e32\u0e14 \u0e2b\u0e21\u0e39\u0e48 3 2569-07-10 12000 01140 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e2d\u0e49\u0e2d\u0e22\u0e2a\u0e14\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e15\u0e31\u0e14\u0e2d\u0e49\u0e2d\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e31\u0e01\u0e23\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 \u8fb2\u6797\u6c34\u7523 440  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e0a\u0e31\u0e22\u0e20\u0e39\u0e21\u0e34 \u30c1\u30e3\u30a4\u30e4\u30d7\u30fc\u30e0\u770c\"},{\"reg_no\":\"0105569142770\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569142770 \u0e1a\u0e08.\u0e40\u0e19\u0e47\u0e01\u0e0b\u0e4c\u0e40\u0e08\u0e19 \u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 10000 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 77\/49  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e40\u0e0b\u0e35\u0e22\u0e25\u0e48\u0e32 \u0e08\u0e23\u0e31\u0e0d13  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 77\/49 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e19\u0e19\u0e08\u0e23\u0e31\u0e0d\u0e2a\u0e19\u0e34\u0e17\u0e27\u0e07\u0e28\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0505569016894\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e35\u0e48\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e42\u0e15\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-30\",\"reg_date_sort\":25690730,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"71103\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"71103\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569016894 \u0e1a\u0e08.\u0e1e\u0e35\u0e48\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e42\u0e15\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-30 10000 71103 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19 \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e08\u0e31\u0e22 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e17\u0e33\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e27\u0e34\u0e17\u0e22\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 162  \u0e16\u0e19\u0e19\u0e1b\u0e48\u0e32\u0e1e\u0e23\u0e49\u0e32\u0e27 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0905569006291\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e31\u0e1f\u0e1f\u0e35\u0e48 \u0e41\u0e1e\u0e25\u0e19\u0e40\u0e19\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-27\",\"reg_date_sort\":25690727,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47912\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47912\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006291 \u0e1a\u0e08.\u0e1e\u0e31\u0e1f\u0e1f\u0e35\u0e48 \u0e41\u0e1e\u0e25\u0e19\u0e40\u0e19\u0e47\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-27 10000 47912 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e32\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e42\u0e17\u0e23\u0e19\u0e34\u0e01\u0e2a\u0e4c(e-commerce) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 195  \u0e0b\u0e2d\u0e22 19 \u0e23\u0e31\u0e15\u0e19\u0e2d\u0e38\u0e17\u0e34\u0e28 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0513569000813\",\"name_th\":\"\u0e2b\u0e08.\u0e20\u0e32\u0e19\u0e38 \u0e1e\u0e31\u0e12\u0e19\u0e32\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96201\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96201\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19\",\"province_ja\":\"\u30e9\u30e0\u30d7\u30fc\u30f3\u770c\",\"search_text\":\"0513569000813 \u0e2b\u0e08.\u0e20\u0e32\u0e19\u0e38 \u0e1e\u0e31\u0e12\u0e19\u0e32 2569-07-25 10000 96201 \u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0b\u0e31\u0e01\u0e0a\u0e38\u0e14\u0e04\u0e23\u0e35\u0e19\u0e23\u0e39\u0e21\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 179\/105  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e25\u0e33\u0e1e\u0e39\u0e19 \u30e9\u30e0\u30d7\u30fc\u30f3\u770c\"},{\"reg_no\":\"0103569008052\",\"name_th\":\"\u0e2b\u0e08.\u0e40\u0e21\u0e04\u0e2d\u0e34\u0e17 \u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"14112\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"14112\uff5c\u88fd\u9020\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569008052 \u0e2b\u0e08.\u0e40\u0e21\u0e04\u0e2d\u0e34\u0e17 \u0e2d\u0e35\u0e0b\u0e35\u0e48 \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e01\u0e32\u0e23\u0e4c\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c 2569-07-24 10000 14112 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e14\u0e40\u0e22\u0e47\u0e1a\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1a\u0e1a \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u88fd\u9020 797\/139-141  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e17\u0e18\u0e34\u0e1e\u0e23 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0303569002923\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e23\u0e39\u0e15\u0e39\u0e48\u0e2b\u0e21\u0e27\u0e01\u0e44\u0e2b\u0e21\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"90002\",\"industry_category\":\"\u82b8\u8853\u30fb\u5a2f\u697d\",\"industry_label\":\"90002\uff5c\u82b8\u8853\u30fb\u5a2f\u697d\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002923 \u0e2b\u0e08.\u0e04\u0e23\u0e39\u0e15\u0e39\u0e48\u0e2b\u0e21\u0e27\u0e01\u0e44\u0e2b\u0e21 2569-07-24 10000 90002 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e40\u0e27\u0e49\u0e19\u0e17\u0e4c \u0e07\u0e32\u0e19\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e15\u0e48\u0e32\u0e07\u0e46 \u82b8\u8853\u30fb\u5a2f\u697d 381\/6  \u0e16\u0e19\u0e19\u0e17\u0e49\u0e32\u0e27\u0e2a\u0e38\u0e23\u0e30 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0945569000781\",\"name_th\":\"\u0e1a\u0e08.\u0e27\u0e35\u0e42\u0e01 \u0e0b\u0e32\u0e1f\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-24\",\"reg_date_sort\":25690724,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0945569000781 \u0e1a\u0e08.\u0e27\u0e35\u0e42\u0e01 \u0e0b\u0e32\u0e1f\u0e32\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-24 10000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e40\u0e40\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 43  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35 \u30d1\u30c3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569136788\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e15\u0e15\u0e32 \u0e04\u0e27\u0e2d\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47732\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47732\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136788 \u0e1a\u0e08.\u0e2d\u0e31\u0e15\u0e15\u0e32 \u0e04\u0e27\u0e2d\u0e15\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 10000 47732 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 33  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e19\u0e17\u0e23\u0e35  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 33\/156 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569136796\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-21\",\"reg_date_sort\":25690721,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69100\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69100\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569136796 \u0e1a\u0e08.\u0e41\u0e2d\u0e25 \u0e40\u0e04 \u0e40\u0e2d\u0e47\u0e19 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e2d\u0e2a\u0e40\u0e18\u0e2d\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e19\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-21 10000 69100 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e14\u0e35\u0e41\u0e1e\u0e48\u0e07 \u0e04\u0e14\u0e35\u0e2d\u0e32\u0e0d\u0e32 \u0e04\u0e14\u0e35\u0e20\u0e32\u0e29\u0e35\u0e2d\u0e32\u0e01\u0e23 \u0e04\u0e14\u0e35\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e04\u0e14\u0e35\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e2b\u0e49\u0e32\u0e07\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e41\u0e25\u0e30 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 88  \u0e0b\u0e2d\u0e22 \u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e0737\/1 (\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e27\u0e34\u0e01\u0e23\u0e21\u0e4c) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569027253\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e42\u0e25\u0e27\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47721\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47721\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569027253 \u0e1a\u0e08.\u0e40\u0e1f\u0e25\u0e42\u0e25\u0e27\u0e34\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 10000 47721 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e19\u0e33\u0e40\u0e02\u0e49\u0e32 \u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21 \u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19 \u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 88\/68  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 9 \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e23\u0e32\u0e0a\u0e1e\u0e24\u0e01\u0e29\u0e4c-\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e351 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0415569003645\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e19\u0e21\u0e2a\u0e14 \u0e22\u0e39\u0e14\u0e35\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0415569003645 \u0e1a\u0e08.\u0e14\u0e39\u0e19\u0e21\u0e2a\u0e14 \u0e22\u0e39\u0e14\u0e35\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 10000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5bbf\u6cca\u30fb\u98f2\u98df 87\/1  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e40\u0e07\u0e34\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u30a6\u30c9\u30fc\u30f3\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0105569131883\",\"name_th\":\"\u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e40\u0e27\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131883 \u0e1a\u0e08.\u0e1a\u0e25\u0e39\u0e40\u0e27\u0e25 \u0e04\u0e2d\u0e19\u0e0b\u0e31\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 10000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 95\/517  \u0e0b\u0e2d\u0e22 \u0e23\u0e34\u0e21\u0e04\u0e25\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e42\u0e02\u0e19\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0655569002230\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e39\u0e19\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63990\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63990\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01\",\"province_ja\":\"\u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\",\"search_text\":\"0655569002230 \u0e1a\u0e08.\u0e14\u0e39\u0e19\u0e32 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 10000 63990 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1c\u0e25\u0e34\u0e15 \u0e08\u0e31\u0e14\u0e17\u0e33 \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e49\u0e27\u0e22\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e01\u0e25\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e0b\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e02\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 179  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 8 \u0e08.\u0e1e\u0e34\u0e29\u0e13\u0e38\u0e42\u0e25\u0e01 \u30d4\u30c3\u30b5\u30cc\u30ed\u30fc\u30af\u770c\"},{\"reg_no\":\"0105569131018\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e42\u0e2b\u0e25\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131018 \u0e1a\u0e08.\u0e42\u0e1b\u0e23\u0e42\u0e2b\u0e25\u0e14 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 10000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 561\/301  \u0e16\u0e19\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569025790\",\"name_th\":\"\u0e1a\u0e08.\u0e1e\u0e2d\u0e22\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47911\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47911\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025790 \u0e1a\u0e08.\u0e1e\u0e2d\u0e22\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e23\u0e14\u0e14\u0e34\u0e49\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-09 10000 47911 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-commerce) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e44\u0e27\u0e49\u0e43\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 (\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e21\u0e48\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07) \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 94\/88  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e34\u0e27\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c 9 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e0b\u0e2d\u0e22 23 \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0203569002967\",\"name_th\":\"\u0e2b\u0e08.\u0e08\u0e23\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-09\",\"reg_date_sort\":25690709,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0203569002967 \u0e2b\u0e08.\u0e08\u0e23\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e13\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-09 10000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 172\/9  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 \u30c1\u30e7\u30f3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0465569000859\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-08\",\"reg_date_sort\":25690708,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46109\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46109\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c\",\"province_ja\":\"\u30ab\u30fc\u30e9\u30b7\u30f3\u770c\",\"search_text\":\"0465569000859 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e21\u0e08\u0e35\u0e27\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-08 10000 46109 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e17\u0e2d\u0e07 \u0e19\u0e32\u0e01 \u0e40\u0e07\u0e34\u0e19 \u0e40\u0e1e\u0e0a\u0e23 \u0e1e\u0e25\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e2d\u0e37\u0e48\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e17\u0e33\u0e40\u0e17\u0e35\u0e22\u0e21\u0e2a\u0e34\u0e48\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27  \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e32\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19 \u0e04\u0e48\u0e32\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e08\u0e49\u0e32\u0e07 \u0e22\u0e01\u0e40\u0e27\u0e49\u0e19 \u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e1a\u0e31\u0e27\u0e42\u0e14\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e08.\u0e01\u0e32\u0e2c\u0e2a\u0e34\u0e19\u0e18\u0e38\u0e4c \u30ab\u30fc\u30e9\u30b7\u30f3\u770c\"},{\"reg_no\":\"0483569000504\",\"name_th\":\"\u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"59201\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"59201\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\",\"search_text\":\"0483569000504 \u0e2b\u0e08.\u0e0b\u0e35\u0e40\u0e2d\u0e2a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d 2569-07-07 10000 59201 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e01\u0e22\u0e4c\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e0b\u0e35\u0e23\u0e35\u0e48\u0e2a\u0e4c\u0e08\u0e35\u0e19\u0e41\u0e25\u0e30\u0e40\u0e1e\u0e25\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07 \u60c5\u5831\u901a\u4fe1\u30fbit 259  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 15 \u0e08.\u0e19\u0e04\u0e23\u0e1e\u0e19\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30ce\u30e0\u770c\"},{\"reg_no\":\"0505569015367\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e41\u0e08\u0e48\u0e21\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569015367 \u0e1a\u0e08.\u0e41\u0e21\u0e48\u0e41\u0e08\u0e48\u0e21\u0e17\u0e31\u0e27\u0e23\u0e4c\u0e41\u0e2d\u0e19\u0e14\u0e4c\u0e17\u0e23\u0e32\u0e40\u0e27\u0e25 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-07 10000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 155  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 16 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"},{\"reg_no\":\"0105569126952\",\"name_th\":\"\u0e1a\u0e08.\u0e0b\u0e32\u0e2e\u0e32\u0e23\u0e48\u0e32 \u0e40\u0e2d\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56101\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56101\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569126952 \u0e1a\u0e08.\u0e0b\u0e32\u0e2e\u0e32\u0e23\u0e48\u0e32 \u0e40\u0e2d\u0e1f \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e1a\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 10000 56101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e23\u0e49\u0e32\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e23\u0e49\u0e32\u0e19\u0e01\u0e32\u0e41\u0e1f \u0e20\u0e31\u0e15\u0e15\u0e32\u0e04\u0e32\u0e23 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e1a\u0e32\u0e23\u0e4c \u0e44\u0e19\u0e15\u0e4c\u0e04\u0e25\u0e31\u0e1a \u5bbf\u6cca\u30fb\u98f2\u98df 33, 33\/1, 33\/2, 33\/3  \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 11 (\u0e44\u0e0a\u0e22\u0e22\u0e28) \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0125569025013\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"69200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"69200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0125569025013 \u0e1a\u0e08.\u0e25\u0e1e\u0e31\u0e17\u0e18\u0e4c \u0e41\u0e2d\u0e04\u0e40\u0e04\u0e49\u0e32\u0e19\u0e4c\u0e15\u0e34\u0e49\u0e07 \u0e41\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e0b\u0e2d\u0e23\u0e4c\u0e27\u0e34\u0e2a\u0e40\u0e0b\u0e2a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 10000 69200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22  \u0e17\u0e32\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35  \u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21  \u0e17\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 222\/49  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e40\u0e1f\u0e04\u0e40\u0e1e\u0e25\u0e2a\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c-\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e44\u0e17\u0e23\u0e21\u0e49\u0e32 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e0b\u0e2d\u0e22 \u0e44\u0e17\u0e23\u0e21\u0e49\u0e32 7 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e15\u0e19\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23\u0e4c \u0e08.\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u30ce\u30f3\u30bf\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0135569020704\",\"name_th\":\"\u0e1a\u0e08.\u0e20\u0e27\u0e31\u0e19\u0e15\u0e38 \u0e40\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56210\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56210\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0135569020704 \u0e1a\u0e08.\u0e20\u0e27\u0e31\u0e19\u0e15\u0e38 \u0e40\u0e15 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-06 10000 56210 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e17\u0e33\u0e1a\u0e38\u0e0d \u0e07\u0e32\u0e19\u0e21\u0e07\u0e04\u0e25\u0e2a\u0e21\u0e23\u0e2a \u0e07\u0e32\u0e19\u0e28\u0e1e \u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07 \u0e07\u0e32\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e38\u0e01\u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5bbf\u6cca\u30fb\u98f2\u98df 107\/338  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e39\u0e25\u0e28\u0e23\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0835569012489\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68202\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68202\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15\",\"province_ja\":\"\u30d7\u30fc\u30b1\u30c3\u30c8\u770c\",\"search_text\":\"0835569012489 \u0e1a\u0e08.\u0e40\u0e2d\u0e47\u0e19\u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c \u0e41\u0e21\u0e40\u0e19\u0e08\u0e40\u0e21\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-04 10000 68202 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e14\u0e39\u0e41\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2a\u0e31\u0e07\u0e2b\u0e32\u0e23\u0e34\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u4e0d\u52d5\u7523 23\/95  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 2 \u0e08.\u0e20\u0e39\u0e40\u0e01\u0e47\u0e15 \u30d7\u30fc\u30b1\u30c3\u30c8\u770c\"},{\"reg_no\":\"0103569006866\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e31\u0e01\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85410\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85410\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0103569006866 \u0e2b\u0e08.\u0e23\u0e31\u0e01\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 2569-07-03 10000 85410 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2a\u0e2d\u0e19 \u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u0e01\u0e32\u0e23\u0e25\u0e14\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e01\u0e32\u0e23\u0e22\u0e37\u0e14\u0e40\u0e2b\u0e22\u0e35\u0e22\u0e14\u0e01\u0e25\u0e49\u0e32\u0e21\u0e40\u0e19\u0e37\u0e49\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e42\u0e14\u0e22\u0e40\u0e17\u0e23\u0e19\u0e40\u0e19\u0e2d\u0e23\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u6559\u80b2 9\/46  \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e32\u0e20\u0e34\u0e1a\u0e32\u0e255 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569125841\",\"name_th\":\"\u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"74200\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"74200\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569125841 \u0e1a\u0e08.\u0e21\u0e34\u0e25\u0e32\u0e40\u0e04\u0e34\u0e25 \u0e04\u0e2d\u0e21\u0e40\u0e1e\u0e25\u0e47\u0e01\u0e0b\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 10000 74200 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07\u0e20\u0e32\u0e1e \u0e0a\u0e48\u0e32\u0e07\u0e41\u0e15\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32 \u0e0a\u0e48\u0e32\u0e07\u0e17\u0e33\u0e1c\u0e21 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 171  \u0e16\u0e19\u0e19\u0e27\u0e31\u0e07\u0e40\u0e14\u0e34\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0765569001429\",\"name_th\":\"\u0e1a\u0e08.\u0e41\u0e2d\u0e1f\u0e1f\u0e34\u0e25\u0e34\u0e40\u0e2d\u0e17 \u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-03\",\"reg_date_sort\":25690703,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"96309\",\"industry_category\":\"\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"96309\uff5c\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35\",\"province_ja\":\"\u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\",\"search_text\":\"0765569001429 \u0e1a\u0e08.\u0e41\u0e2d\u0e1f\u0e1f\u0e34\u0e25\u0e34\u0e40\u0e2d\u0e17 \u0e21\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-03 10000 96309 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e41\u0e0a\u0e23\u0e4c\u0e25\u0e34\u0e07\u0e04\u0e4c\u0e02\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e04\u0e48\u0e32\u0e04\u0e2d\u0e21\u0e21\u0e34\u0e0a\u0e0a\u0e31\u0e48\u0e19 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e32\u0e22\u0e15\u0e23\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e15\u0e25\u0e32\u0e14\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9 1415\/28  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e2d\u0e40\u0e14\u0e19 \u0e16\u0e19\u0e19\u0e0a\u0e25\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19(\u0e17\u0e23\u0e32\u0e22\u0e43\u0e15\u0e49) \u0e08.\u0e40\u0e1e\u0e0a\u0e23\u0e1a\u0e38\u0e23\u0e35 \u30da\u30c3\u30c1\u30e3\u30d6\u30ea\u30fc\u770c\"},{\"reg_no\":\"0105569124666\",\"name_th\":\"\u0e1a\u0e08.\u0e42\u0e19\u0e19\u0e2d\u0e31\u0e19\u0e42\u0e19\u0e19 \u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124666 \u0e1a\u0e08.\u0e42\u0e19\u0e19\u0e2d\u0e31\u0e19\u0e42\u0e19\u0e19 \u0e1f\u0e34\u0e25\u0e4c\u0e21 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 10000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e2b\u0e23\u0e37\u0e2d \u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e07\u0e08\u0e32\u0e01\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2a\u0e34\u0e48\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e23\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e42\u0e06\u0e29\u0e13\u0e32\u0e44\u0e1b\u0e25\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c \u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23 \u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e17\u0e32\u0e07\u0e27\u0e34\u0e17\u0e22\u0e38\u0e41\u0e25\u0e30\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e19\u0e2d\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e0a\u0e48\u0e19 \u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e1b\u0e49\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28 \u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e15\u0e39\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e23\u0e16\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e35\u0e48\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1a\u0e19\u0e41\u0e1c\u0e48\u0e19\u0e1b\u0e49\u0e32\u0e22\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e23\u0e13\u0e23\u0e07\u0e04\u0e4c\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08\u0e41\u0e25\u0e30\u0e23\u0e31\u0e01\u0e29\u0e32\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e27\u0e49 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e13 \u0e08\u0e38\u0e14\u0e02\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e42\u0e06\u0e29\u0e13\u0e32\u0e17\u0e32\u0e07\u0e08\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e15\u0e23\u0e07\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 514  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e23\u0e32\u0e18\u0e23\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e0b\u0e2d\u0e22 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23 44 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0735569006684\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e23\u0e34\u0e0a \u0e42\u0e0b \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0735569006684 \u0e1a\u0e08.\u0e40\u0e2d\u0e1e\u0e35 \u0e23\u0e34\u0e0a \u0e42\u0e0b \u0e23\u0e34\u0e0a \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 10000 56302 \u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1a\u0e40\u0e01\u0e2d\u0e23\u0e35\u0e48\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u5bbf\u6cca\u30fb\u98f2\u98df 76  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0905569005198\",\"name_th\":\"\u0e1a\u0e08.\u0e15\u0e30\u0e2b\u0e25\u0e34\u0e27\u0e40\u0e15\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"56302\",\"industry_category\":\"\u5bbf\u6cca\u30fb\u98f2\u98df\",\"industry_label\":\"56302\uff5c\u5bbf\u6cca\u30fb\u98f2\u98df\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569005198 \u0e1a\u0e08.\u0e15\u0e30\u0e2b\u0e25\u0e34\u0e27\u0e40\u0e15\u0e49\u0e19\u0e23\u0e30\u0e1a\u0e33 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 10000 56302 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u5bbf\u6cca\u30fb\u98f2\u98df 102  \u0e16\u0e19\u0e19\u0e19\u0e34\u0e1e\u0e31\u0e17\u0e18\u0e4c\u0e2d\u0e38\u0e17\u0e34\u0e28 2 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0955569000471\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e27\u0e32\u0e23\u0e35\u0e0b\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":10000,\"capital_display\":\"10,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"79120\",\"industry_category\":\"\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"79120\uff5c\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e22\u0e30\u0e25\u0e32\",\"province_ja\":\"\u30e4\u30e9\u30fc\u770c\",\"search_text\":\"0955569000471 \u0e1a\u0e08.\u0e2d\u0e31\u0e25\u0e27\u0e32\u0e23\u0e35\u0e0b\u0e39\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 10000 79120 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e08\u0e31\u0e14\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1e\u0e32\u0e1c\u0e39\u0e49\u0e41\u0e2a\u0e27\u0e07\u0e1a\u0e38\u0e0d\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e2e\u0e31\u0e08\u0e0d\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e21\u0e40\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e13 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0b\u0e32\u0e2d\u0e38\u0e14\u0e35\u0e2d\u0e32\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22 \u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9 59  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e07\u0e22\u0e32\u0e27\u0e35 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e08.\u0e22\u0e30\u0e25\u0e32 \u30e4\u30e9\u30fc\u770c\"},{\"reg_no\":\"0453569000971\",\"name_th\":\"\u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e21\u0e35. \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07\",\"reg_date\":\"2569-07-06\",\"reg_date_sort\":25690706,\"capital_num\":8000,\"capital_display\":\"8,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"43210\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"43210\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14\",\"province_ja\":\"\u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\",\"search_text\":\"0453569000971 \u0e2b\u0e08.\u0e17\u0e2d\u0e07\u0e21\u0e35. \u0e40\u0e2d\u0e47\u0e19\u0e08\u0e34\u0e40\u0e19\u0e35\u0e22\u0e23\u0e34\u0e48\u0e07 2569-07-06 8000 43210 \u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e1b\u0e32 \u0e07\u0e32\u0e19\u0e41\u0e2d\u0e23\u0e4c \u0e07\u0e32\u0e19solar cell \u5efa\u8a2d 71  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e09\u0e27\u0e30 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 5 \u0e08.\u0e23\u0e49\u0e2d\u0e22\u0e40\u0e2d\u0e47\u0e14 \u30ed\u30fc\u30a4\u30a8\u30c3\u30c8\u770c\"},{\"reg_no\":\"0303569002559\",\"name_th\":\"\u0e2b\u0e08.\u0e1a\u0e35\u0e40\u0e2d \u0e2a\u0e42\u0e15\u0e23\u0e4c\",\"reg_date\":\"2569-07-04\",\"reg_date_sort\":25690704,\"capital_num\":7000,\"capital_display\":\"7,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63112\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63112\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002559 \u0e2b\u0e08.\u0e1a\u0e35\u0e40\u0e2d \u0e2a\u0e42\u0e15\u0e23\u0e4c 2569-07-04 7000 63112 \u0e02\u0e32\u0e22\u0e2a\u0e48\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e41\u0e2d\u0e1e\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 30020418043  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2b\u0e19\u0e2d\u0e07\u0e01\u0e23\u0e32\u0e14 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 13 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0102569000140\",\"name_th\":\"\u0e2b\u0e2a.\u0e27\u0e2a\u0e31\u0e19\u0e15\u0e4c \u0e41\u0e1e\u0e47\u0e04\u0e01\u0e34\u0e49\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19\",\"reg_date\":\"2569-07-25\",\"reg_date_sort\":25690725,\"capital_num\":5100,\"capital_display\":\"5,100 \u0e1a\u0e32\u0e17\",\"objective_code\":\"70209\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"70209\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0102569000140 \u0e2b\u0e2a.\u0e27\u0e2a\u0e31\u0e19\u0e15\u0e4c \u0e41\u0e1e\u0e47\u0e04\u0e01\u0e34\u0e49\u0e07 \u0e42\u0e0b\u0e25\u0e39\u0e0a\u0e31\u0e48\u0e19 2569-07-25 5100 70209 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 21\/133  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e35\u0e40\u0e08\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e2e\u0e21 14  \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 133 \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 93 \u0e41\u0e22\u0e01 \u0e1e\u0e36\u0e48\u0e07\u0e21\u0e35 1 \u0e16\u0e19\u0e19\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0815569002203\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e39\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-22\",\"reg_date_sort\":25690722,\"capital_num\":5000,\"capital_display\":\"5,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"73101\",\"industry_category\":\"\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"industry_label\":\"73101\uff5c\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9\",\"province_th\":\"\u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48\",\"province_ja\":\"\u30af\u30e9\u30d3\u30fc\u770c\",\"search_text\":\"0815569002203 \u0e1a\u0e08.\u0e17\u0e39\u0e40\u0e2d\u0e47\u0e19 \u0e04\u0e2d\u0e19\u0e40\u0e19\u0e04\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-22 5000 73101 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a  \u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21  \u0e08\u0e31\u0e14\u0e17\u0e33  \u0e08\u0e31\u0e14\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48\u0e2a\u0e16\u0e34\u0e15\u0e34  \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e17\u0e32\u0e07\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21  \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21  \u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e01\u0e23\u0e23\u0e21 \u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e1c\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9 244  \u0e16\u0e19\u0e19\u0e2d\u0e48\u0e32\u0e27\u0e25\u0e36\u0e01-\u0e1e\u0e23\u0e30\u0e41\u0e2a\u0e07 \u0e08.\u0e01\u0e23\u0e30\u0e1a\u0e35\u0e48 \u30af\u30e9\u30d3\u30fc\u770c\"},{\"reg_no\":\"0303569002885\",\"name_th\":\"\u0e2b\u0e08.\u0e23\u0e34\u0e04\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1e\u0e25\u0e31\u0e2a\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":4000,\"capital_display\":\"4,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85500\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85500\uff5c\u6559\u80b2\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\",\"search_text\":\"0303569002885 \u0e2b\u0e08.\u0e23\u0e34\u0e04\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1e\u0e25\u0e31\u0e2a 2569-07-23 4000 85500 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e19\u0e35\u0e49 \u0e41\u0e01\u0e48\u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d \u0e2a\u0e32\u0e02\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01. \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e02. \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e0a\u0e34\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19 \u0e04. \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e07. \u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04 \u0e08. \u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22 \u0e09. \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e20\u0e39\u0e21\u0e34\u0e20\u0e32\u0e04 \u0e0a. \u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e0b. \u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e0c. \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2a\u0e34\u0e19\u0e40\u0e0a\u0e37\u0e48\u0e2d \u6559\u80b2 234\/374  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e38\u0e23\u0e19\u0e32\u0e23\u0e35\u0e22\u0e4c\u0e27\u0e34\u0e25\u0e25\u0e4c \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e32\u0e30 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 3 \u0e08.\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u30ca\u30b3\u30fc\u30f3\u30e9\u30fc\u30c1\u30e3\u30b7\u30fc\u30de\u30fc\u770c\"},{\"reg_no\":\"0843569001442\",\"name_th\":\"\u0e2b\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c\u0e27\u0e31\u0e19 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\",\"reg_date\":\"2569-07-23\",\"reg_date_sort\":25690723,\"capital_num\":2000,\"capital_display\":\"2,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47413\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47413\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0843569001442 \u0e2b\u0e08.\u0e04\u0e2d\u0e19\u0e40\u0e19\u0e47\u0e01\u0e15\u0e4c\u0e27\u0e31\u0e19 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04 2569-07-23 2000 47413 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0b\u0e34\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 \u0e1a\u0e31\u0e15\u0e23\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48 \u0e1a\u0e31\u0e15\u0e23\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e41\u0e17\u0e19\u0e40\u0e07\u0e34\u0e19\u0e2a\u0e14 \u0e04\u0e39\u0e1b\u0e2d\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 96\/47  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e16\u0e19\u0e19\u0e0a\u0e19\u0e40\u0e01\u0e29\u0e21 \u0e08.\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35 \u30b9\u30e9\u30fc\u30c8\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0132569000026\",\"name_th\":\"\u0e2b\u0e2a.\u0e21\u0e35 \u0e44\u0e17\u0e21\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\",\"reg_date\":\"2569-07-07\",\"reg_date_sort\":25690707,\"capital_num\":2000,\"capital_display\":\"2,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"49323\",\"industry_category\":\"\u904b\u8f38\u30fb\u7269\u6d41\",\"industry_label\":\"49323\uff5c\u904b\u8f38\u30fb\u7269\u6d41\",\"province_th\":\"\u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35\",\"province_ja\":\"\u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\",\"search_text\":\"0132569000026 \u0e2b\u0e2a.\u0e21\u0e35 \u0e44\u0e17\u0e21\u0e4c \u0e17\u0e23\u0e32\u0e19\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 2569-07-07 2000 49323 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e41\u0e25\u0e30\u0e02\u0e19\u0e16\u0e48\u0e32\u0e22\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e41\u0e25\u0e30\u0e04\u0e19\u0e42\u0e14\u0e22\u0e2a\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01  \u0e17\u0e32\u0e07\u0e19\u0e49\u0e33  \u0e17\u0e32\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e28  \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e19\u0e33\u0e02\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d\u0e15\u0e32\u0e21\u0e1e\u0e34\u0e18\u0e35\u0e28\u0e38\u0e25\u0e01\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e30\u0e27\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14 \u904b\u8f38\u30fb\u7269\u6d41 603\/400  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e08.\u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u30d1\u30c8\u30a5\u30e0\u30bf\u30fc\u30cb\u30fc\u770c\"},{\"reg_no\":\"0733569000943\",\"name_th\":\"\u0e2b\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e21\u0e35\u0e19\u0e32\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":1500,\"capital_display\":\"1,500 \u0e1a\u0e32\u0e17\",\"objective_code\":\"11043\",\"industry_category\":\"\u88fd\u9020\",\"industry_label\":\"11043\uff5c\u88fd\u9020\",\"province_th\":\"\u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"province_ja\":\"\u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\",\"search_text\":\"0733569000943 \u0e2b\u0e08.\u0e21\u0e35\u0e14\u0e35 \u0e21\u0e35\u0e19\u0e32 2569-07-01 1500 11043 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u88fd\u9020 141  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 10 \u0e08.\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u30ca\u30b3\u30fc\u30f3\u30d1\u30c8\u30e0\u770c\"},{\"reg_no\":\"0905569006399\",\"name_th\":\"\u0e1a\u0e08.\u0e1b\u0e31\u0e49\u0e19\u0e21\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000,\"capital_display\":\"1,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46102\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46102\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006399 \u0e1a\u0e08.\u0e1b\u0e31\u0e49\u0e19\u0e21\u0e32\u0e14\u0e35 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000 46102 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e31\u0e01 \u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e48\u0e2d\u0e44\u0e21\u0e49 \u0e1e\u0e23\u0e34\u0e01\u0e44\u0e17\u0e22 \u0e1e\u0e37\u0e0a\u0e2a\u0e27\u0e19 \u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48 \u0e22\u0e32\u0e40\u0e2a\u0e49\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e14\u0e37\u0e48\u0e21 \u0e19\u0e49\u0e33\u0e41\u0e23\u0e48 \u0e19\u0e49\u0e33\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e2a\u0e38\u0e23\u0e32 \u0e40\u0e1a\u0e35\u0e22\u0e23\u0e4c \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e14 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e49\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e30\u0e40\u0e25\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e38\u0e07\u0e23\u0e2a\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e19\u0e49\u0e33\u0e0b\u0e2d\u0e2a \u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e1e\u0e37\u0e0a \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e31\u0e15\u0e27\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 21  \u0e0b\u0e2d\u0e22 3 \u0e16\u0e19\u0e19\u0e44\u0e17\u0e23\u0e1a\u0e38\u0e23\u0e35 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0905569006402\",\"name_th\":\"\u0e1a\u0e08.\u0e25\u0e32\u0e22\u0e40\u0e25 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-31\",\"reg_date_sort\":25690731,\"capital_num\":1000,\"capital_display\":\"1,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"46495\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"46495\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32\",\"province_ja\":\"\u30bd\u30f3\u30af\u30e9\u30fc\u770c\",\"search_text\":\"0905569006402 \u0e1a\u0e08.\u0e25\u0e32\u0e22\u0e40\u0e25 \u0e2d\u0e34\u0e19\u0e42\u0e19\u0e40\u0e27\u0e0a\u0e31\u0e48\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-31 1000 46495 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e04\u0e2b\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27 \u0e15\u0e39\u0e49\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e1e\u0e31\u0e14\u0e25\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e39\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e2b\u0e21\u0e49\u0e2d\u0e2b\u0e38\u0e07\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e15\u0e32\u0e23\u0e35\u0e14\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e22\u0e47\u0e19 \u0e40\u0e15\u0e32\u0e2d\u0e1a\u0e44\u0e21\u0e42\u0e04\u0e23\u0e40\u0e27\u0e1f \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e30\u0e44\u0e2b\u0e25\u0e48\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 4\/176  \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 6 \u0e0b\u0e2d\u0e22 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e1b\u0e32\u0e25\u0e4c\u0e21\u0e0b\u0e34\u0e15\u0e35\u0e49 \u0e08.\u0e2a\u0e07\u0e02\u0e25\u0e32 \u30bd\u30f3\u30af\u30e9\u30fc\u770c\"},{\"reg_no\":\"0115569025064\",\"name_th\":\"\u0e1a\u0e08.\u0e04\u0e0a\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-29\",\"reg_date_sort\":25690729,\"capital_num\":1000,\"capital_display\":\"1,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"68201\",\"industry_category\":\"\u4e0d\u52d5\u7523\",\"industry_label\":\"68201\uff5c\u4e0d\u52d5\u7523\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569025064 \u0e1a\u0e08.\u0e04\u0e0a\u0e25\u0e31\u0e01\u0e29\u0e21\u0e35 \u0e1e\u0e23\u0e47\u0e2d\u0e1e\u0e40\u0e1e\u0e2d\u0e23\u0e4c\u0e15\u0e35\u0e49 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-29 1000 68201 \u0e40\u0e1b\u0e47\u0e19\u0e19\u0e32\u0e22\u0e2b\u0e19\u0e49\u0e32 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19 \u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e04\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e43\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e43\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2b\u0e32\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e21\u0e32\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u4e0d\u52d5\u7523 748\/35  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1e\u0e24\u0e01\u0e29\u0e32\u0e27\u0e34\u0e27\u0e40\u0e25\u0e0819 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 7 \u0e0b\u0e2d\u0e22 \u0e21\u0e2b\u0e32\u0e0a\u0e31\u0e22 \u0e41\u0e22\u0e011 \u0e16\u0e19\u0e19\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0105569132693\",\"name_th\":\"\u0e1a\u0e08.\u0e17\u0e23\u0e32\u0e27\u0e34\u0e42\u0e01\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-14\",\"reg_date_sort\":25690714,\"capital_num\":1000,\"capital_display\":\"1,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"85492\",\"industry_category\":\"\u6559\u80b2\",\"industry_label\":\"85492\uff5c\u6559\u80b2\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569132693 \u0e1a\u0e08.\u0e17\u0e23\u0e32\u0e27\u0e34\u0e42\u0e01\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-14 1000 85492 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28 \u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c  \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u6559\u80b2 938\/1  \u0e0b\u0e2d\u0e22 \u0e2a.\u0e18\u0e23\u0e13\u0e34\u0e19\u0e17\u0e23\u0e4c 9 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569131794\",\"name_th\":\"\u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e2a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-11\",\"reg_date_sort\":25690711,\"capital_num\":1000,\"capital_display\":\"1,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"62022\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"62022\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569131794 \u0e1a\u0e08.\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27 \u0e40\u0e2d\u0e2a \u0e2a\u0e15\u0e39\u0e14\u0e34\u0e42\u0e2d \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-11 1000 62022 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c \u60c5\u5831\u901a\u4fe1\u30fbit 45  \u0e0b\u0e2d\u0e22 \u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 \u0e17\u0e35\u0e4862 \u0e16\u0e19\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e212 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0105569124861\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-02\",\"reg_date_sort\":25690702,\"capital_num\":1000,\"capital_display\":\"1,000 \u0e1a\u0e32\u0e17\",\"objective_code\":\"41001\",\"industry_category\":\"\u5efa\u8a2d\",\"industry_label\":\"41001\uff5c\u5efa\u8a2d\",\"province_th\":\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"province_ja\":\"\u30d0\u30f3\u30b3\u30af\u90fd\",\"search_text\":\"0105569124861 \u0e1a\u0e08.\u0e2d\u0e34\u0e19\u0e40\u0e0b\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e44\u0e25\u0e19\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-02 1000 41001 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e32\u0e04\u0e32\u0e23  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22  \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e32\u0e23  \u0e16\u0e19\u0e19  \u0e2a\u0e30\u0e1e\u0e32\u0e19  \u0e40\u0e02\u0e37\u0e48\u0e2d\u0e19  \u0e2d\u0e38\u0e42\u0e21\u0e07\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e38\u0e01\u0e0a\u0e19\u0e34\u0e14  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e33\u0e07\u0e32\u0e19\u0e42\u0e22\u0e18\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u5efa\u8a2d 101  \u0e0b\u0e2d\u0e22 \u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2a\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c 24 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u30d0\u30f3\u30b3\u30af\u90fd\"},{\"reg_no\":\"0115569023967\",\"name_th\":\"\u0e1a\u0e08. \u0e40\u0e1a\u0e2a\u0e34\u0e04 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-20\",\"reg_date_sort\":25690720,\"capital_num\":500,\"capital_display\":\"500 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023967 \u0e1a\u0e08. \u0e40\u0e1a\u0e2a\u0e34\u0e04 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-20 500 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 777  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e0a\u0e40\u0e2d \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 (\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14) \u0e01\u0e21.7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023029\",\"name_th\":\"\u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e49\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500,\"capital_display\":\"500 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023029 \u0e1a\u0e08.\u0e2d\u0e2d\u0e23\u0e34\u0e08\u0e34\u0e49\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 777  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e0a\u0e40\u0e2d \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 (\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14) \u0e01\u0e21.7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0115569023037\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-10\",\"reg_date_sort\":25690710,\"capital_num\":500,\"capital_display\":\"500 \u0e1a\u0e32\u0e17\",\"objective_code\":\"47711\",\"industry_category\":\"\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"industry_label\":\"47711\uff5c\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca\",\"province_th\":\"\u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23\",\"province_ja\":\"\u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\",\"search_text\":\"0115569023037 \u0e1a\u0e08.\u0e40\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e1a\u0e34\u0e19 \u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 (\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-10 500 47711 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32 \u0e1c\u0e49\u0e32 \u0e1c\u0e49\u0e32\u0e17\u0e2d\u0e08\u0e32\u0e01\u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e14\u0e49\u0e32\u0e22 \u0e14\u0e49\u0e32\u0e22\u0e22\u0e32\u0e07\u0e22\u0e37\u0e14 \u0e40\u0e2a\u0e49\u0e19\u0e43\u0e22\u0e44\u0e19\u0e25\u0e48\u0e2d\u0e19 \u0e43\u0e22\u0e2a\u0e31\u0e07\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e2a\u0e49\u0e19\u0e14\u0e49\u0e32\u0e22\u0e22\u0e37\u0e14 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e38\u0e48\u0e07\u0e2b\u0e48\u0e21 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e01\u0e32\u0e22 \u0e16\u0e38\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e16\u0e38\u0e07\u0e19\u0e48\u0e2d\u0e07 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e31\u0e07 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e2d\u0e37\u0e48\u0e19 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e2d \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32 \u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca 777  \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e1a\u0e25\u0e34\u0e27\u0e40\u0e2d\u0e0a\u0e40\u0e2d \u0e17\u0e32\u0e27\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e0a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e19\u0e19\u0e40\u0e17\u0e1e\u0e23\u0e31\u0e15\u0e19 (\u0e1a\u0e32\u0e07\u0e19\u0e32-\u0e15\u0e23\u0e32\u0e14) \u0e01\u0e21.7 \u0e08.\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u30b5\u30e0\u30c3\u30c8\u30d7\u30e9\u30fc\u30ab\u30fc\u30f3\u770c\"},{\"reg_no\":\"0505569014743\",\"name_th\":\"\u0e1a\u0e08.\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e2d\u0e32\u0e21\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14\",\"reg_date\":\"2569-07-01\",\"reg_date_sort\":25690701,\"capital_num\":10,\"capital_display\":\"10 \u0e1a\u0e32\u0e17\",\"objective_code\":\"63113\",\"industry_category\":\"\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"industry_label\":\"63113\uff5c\u60c5\u5831\u901a\u4fe1\u30fbIT\",\"province_th\":\"\u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\",\"province_ja\":\"\u30c1\u30a2\u30f3\u30de\u30a4\u770c\",\"search_text\":\"0505569014743 \u0e1a\u0e08.\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e2d\u0e32\u0e21\u0e31\u0e19\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 2569-07-01 10 63113 \u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c  \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e22\u0e41\u0e1e\u0e23\u0e48 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25  \u0e2a\u0e37\u0e48\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c \u0e19\u0e34\u0e22\u0e32\u0e22 \u0e01\u0e32\u0e23\u0e4c\u0e15\u0e39\u0e19 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17  \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e04\u0e23\u0e14\u0e34\u0e15 \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e47\u0e15 \u60c5\u5831\u901a\u4fe1\u30fbit 170\/44  \u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e31\u0e19\u0e15\u0e49\u0e19\u0e40\u0e1b\u0e32 (\u0e19\u0e1e\u0e40\u0e01\u0e49\u0e32) \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 1 \u0e08.\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u30c1\u30a2\u30f3\u30de\u30a4\u770c\"}]<\/script>\n            <\/div>\n            <script>\n            (function(){\n                var root = document.getElementById('adc-nrc-2607-2746deb9');\n                if (!root) return;\n                var dataEl = root.querySelector('.adc-nrc__data');\n                var records = [];\n                try { records = JSON.parse(dataEl ? dataEl.textContent : '[]') || []; } catch(e) { records = []; }\n                var search = root.querySelector('.adc-nrc__search');\n                var industry = root.querySelector('.adc-nrc__industry-filter');\n                var sort = root.querySelector('.adc-nrc__sort');\n                var perPage = root.querySelector('.adc-nrc__per-page');\n                var status = root.querySelector('.adc-nrc__status');\n                var cards = root.querySelector('.adc-nrc__cards');\n                var pager = root.querySelector('.adc-nrc__pager');\n                var page = 1;\n\n                function esc(s) {\n                    return String(s == null ? '' : s).replace(\/[&<>\"']\/g, function(c){\n                        return {'&':'&amp;','<':'&lt;','>':'&gt;','\"':'&quot;',\"'\":'&#039;'}[c];\n                    });\n                }\n                function lower(s) { return String(s == null ? '' : s).toLowerCase(); }\n                function numberFormat(n) {\n                    try { return new Intl.NumberFormat('ja-JP').format(n); } catch(e) { return String(n); }\n                }\n                function buildIndustryOptions() {\n                    if (!industry) return;\n                    var counts = {};\n                    records.forEach(function(r){\n                        var c = r.industry_category || '\u672a\u5206\u985e';\n                        counts[c] = (counts[c] || 0) + 1;\n                    });\n                    var preferred = ['\u4e0d\u52d5\u7523','\u5efa\u8a2d','\u5bbf\u6cca\u30fb\u98f2\u98df','\u5378\u58f2\u30fb\u5c0f\u58f2\u30fb\u81ea\u52d5\u8eca','\u88fd\u9020','\u60c5\u5831\u901a\u4fe1\u30fbIT','\u5c02\u9580\u30fb\u6280\u8853\u30b5\u30fc\u30d3\u30b9','\u4e8b\u52d9\u30fb\u652f\u63f4\u30b5\u30fc\u30d3\u30b9','\u904b\u8f38\u30fb\u7269\u6d41','\u91d1\u878d\u30fb\u4fdd\u967a','\u533b\u7642\u30fb\u798f\u7949','\u6559\u80b2','\u305d\u306e\u4ed6\u30b5\u30fc\u30d3\u30b9','\u305d\u306e\u4ed6\u30fb\u672a\u5206\u985e','\u672a\u5206\u985e'];\n                    var keys = Object.keys(counts).sort(function(a,b){ return a.localeCompare(b, 'ja'); });\n                    keys.sort(function(a,b){\n                        var ia = preferred.indexOf(a), ib = preferred.indexOf(b);\n                        if (ia === -1) ia = 999;\n                        if (ib === -1) ib = 999;\n                        if (ia === ib) return a.localeCompare(b, 'ja');\n                        return ia - ib;\n                    });\n                    keys.forEach(function(k){\n                        var opt = document.createElement('option');\n                        opt.value = k;\n                        opt.textContent = k + '\uff08' + counts[k] + '\uff09';\n                        industry.appendChild(opt);\n                    });\n                }\n                function filteredSorted() {\n                    var q = search ? lower(search.value).trim() : '';\n                    var cat = industry ? industry.value : '';\n                    var out = records.filter(function(r){\n                        if (cat && r.industry_category !== cat) return false;\n                        if (q && lower(r.search_text || '').indexOf(q) === -1) return false;\n                        return true;\n                    });\n                    var mode = sort ? sort.value : 'capital_desc';\n                    out.sort(function(a,b){\n                        if (mode === 'capital_asc') return (a.capital_num || 0) - (b.capital_num || 0);\n                        if (mode === 'date_desc') return (b.reg_date_sort || 0) - (a.reg_date_sort || 0);\n                        if (mode === 'date_asc') return (a.reg_date_sort || 0) - (b.reg_date_sort || 0);\n                        if (mode === 'regno_asc') return String(a.reg_no || '').localeCompare(String(b.reg_no || ''));\n                        return (b.capital_num || 0) - (a.capital_num || 0);\n                    });\n                    return out;\n                }\n                function renderCard(r, index) {\n                    var cap = r.capital_display || (r.capital_num ? numberFormat(r.capital_num) + ' \u0e1a\u0e32\u0e17' : '');\n                    var industryLabel = r.industry_category || '\u672a\u5206\u985e';\n                    if (r.objective_code) industryLabel += '\uff08' + r.objective_code + '\uff09';\n                    return '<article class=\"adc-nrc-card\">'\n                        + '<div class=\"adc-nrc-card__top\">'\n                        + '<span class=\"adc-nrc-card__rank\">#' + esc(index) + '<\/span>'\n                        + '<span class=\"adc-nrc-card__industry\">' + esc(industryLabel) + '<\/span>'\n                        + '<\/div>'\n                        + '<h3 class=\"adc-nrc-card__name\">' + esc(r.name_th || '\u540d\u79f0\u4e0d\u660e') + '<\/h3>'\n                        + '<dl class=\"adc-nrc-card__facts\">'\n                        + '<div><dt>\u6cd5\u4eba\u756a\u53f7<\/dt><dd>' + esc(r.reg_no) + '<\/dd><\/div>'\n                        + '<div><dt>\u8cc7\u672c\u91d1<\/dt><dd>' + esc(cap) + '<\/dd><\/div>'\n                        + '<div><dt>\u767b\u8a18\u65e5<\/dt><dd>' + esc(r.reg_date) + '<\/dd><\/div>'\n                        + '<div><dt>\u6240\u5728\u5730<\/dt><dd>' + esc(r.province_ja || '\u90fd\u770c\u5224\u5225\u4e0d\u53ef') + '<\/dd><\/div>'\n                        + '<\/dl>'\n                        + '<\/article>';\n                }\n                function renderPager(totalPages) {\n                    if (!pager) return;\n                    if (totalPages <= 1) { pager.innerHTML = ''; return; }\n                    var html = '';\n                    html += '<button type=\"button\" class=\"adc-nrc__page-btn\" data-page=\"' + (page - 1) + '\"' + (page <= 1 ? ' disabled' : '') + '>\u524d\u3078<\/button>';\n                    var start = Math.max(1, page - 2);\n                    var end = Math.min(totalPages, page + 2);\n                    if (start > 1) {\n                        html += '<button type=\"button\" class=\"adc-nrc__page-btn\" data-page=\"1\">1<\/button>';\n                        if (start > 2) html += '<span class=\"adc-nrc__page-gap\">\u2026<\/span>';\n                    }\n                    for (var i = start; i <= end; i++) {\n                        html += '<button type=\"button\" class=\"adc-nrc__page-btn' + (i === page ? ' is-current' : '') + '\" data-page=\"' + i + '\">' + i + '<\/button>';\n                    }\n                    if (end < totalPages) {\n                        if (end < totalPages - 1) html += '<span class=\"adc-nrc__page-gap\">\u2026<\/span>';\n                        html += '<button type=\"button\" class=\"adc-nrc__page-btn\" data-page=\"' + totalPages + '\">' + totalPages + '<\/button>';\n                    }\n                    html += '<button type=\"button\" class=\"adc-nrc__page-btn\" data-page=\"' + (page + 1) + '\"' + (page >= totalPages ? ' disabled' : '') + '>\u6b21\u3078<\/button>';\n                    pager.innerHTML = html;\n                    var buttons = pager.querySelectorAll('button[data-page]');\n                    Array.prototype.forEach.call(buttons, function(btn){\n                        btn.addEventListener('click', function(){\n                            var p = parseInt(btn.getAttribute('data-page'), 10);\n                            if (!isNaN(p)) { page = Math.max(1, Math.min(totalPages, p)); render(); root.scrollIntoView({block:'start', behavior:'smooth'}); }\n                        });\n                    });\n                }\n                function render() {\n                    var list = filteredSorted();\n                    var pp = perPage ? parseInt(perPage.value, 10) : 100;\n                    if ([50,100,200,500].indexOf(pp) === -1) pp = 100;\n                    var totalPages = Math.max(1, Math.ceil(list.length \/ pp));\n                    if (page > totalPages) page = totalPages;\n                    var start = (page - 1) * pp;\n                    var shown = list.slice(start, start + pp);\n                    if (status) {\n                        if (!list.length) {\n                            status.textContent = '\u8a72\u5f53\u3059\u308b\u6cd5\u4eba\u306f\u3042\u308a\u307e\u305b\u3093\u3002';\n                        } else {\n                            status.textContent = '\u8a72\u5f53 ' + numberFormat(list.length) + '\u4ef6\u4e2d ' + numberFormat(start + 1) + '\u301c' + numberFormat(start + shown.length) + '\u4ef6\u3092\u8868\u793a';\n                        }\n                    }\n                    if (cards) {\n                        cards.innerHTML = shown.map(function(r, i){ return renderCard(r, start + i + 1); }).join('');\n                    }\n                    renderPager(totalPages);\n                }\n                buildIndustryOptions();\n                [search, industry, sort, perPage].forEach(function(el){\n                    if (!el) return;\n                    el.addEventListener('input', function(){ page = 1; render(); });\n                    el.addEventListener('change', function(){ page = 1; render(); });\n                });\n                render();\n            })();\n            <\/script>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":7216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"\u30a2\u30b8\u30a2\u30fb\u30c0\u30a4\u30ca\u30df\u30c3\u30af\u30fb\u30b3\u30df\u30e5\u30cb\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba\u682a\u5f0f\u4f1a\u793e\"\/>\n\t<meta name=\"google-site-verification\" content=\"coydszDUidafXsSVg7vlzF5l4A_0-vF7g2IYDq1YeYQ\" \/>\n\t<meta name=\"keywords\" content=\"\u30bf\u30a4\u6cd5\u4eba\u7d4c\u55b6\u5b9f\u52d9\u60c5\u5831\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ja_JP\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u30bf\u30a4\u306b\u5e83\u304c\u308b\u7d4c\u55b6\u306b\u3059\u3050\u306b\u6d3b\u304b\u305b\u308b\u6700\u65b0\u60c5\u5831\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8| \u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-08-05T11:13:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-05T11:13:38+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AsiaDynamicCommunications\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8| \u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#article\",\"name\":\"\\u30bf\\u30a4\\u30672026\\u5e747\\u6708\\u306b\\u65b0\\u898f\\u767b\\u8a18\\u3055\\u308c\\u305f\\u6cd5\\u4eba\\u30ea\\u30b9\\u30c8| \\u30bf\\u30a4\\u30d3\\u30b8\\u30cd\\u30b9\\u6700\\u65b0\\u60c5\\u5831\",\"headline\":\"\\u30bf\\u30a4\\u30672026\\u5e747\\u6708\\u306b\\u65b0\\u898f\\u767b\\u8a18\\u3055\\u308c\\u305f\\u6cd5\\u4eba\\u30ea\\u30b9\\u30c8\",\"author\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/author\\\/takashina#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/DBD-cover.jpg\",\"width\":651,\"height\":366},\"datePublished\":\"2026-08-05T20:13:38+09:00\",\"dateModified\":\"2026-08-05T20:13:38+09:00\",\"inLanguage\":\"ja\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#webpage\"},\"articleSection\":\"\\u30bf\\u30a4\\u6cd5\\u4eba\\u7d4c\\u55b6\\u5b9f\\u52d9\\u60c5\\u5831\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/category\\\/corporate#listItem\",\"name\":\"\\u30bf\\u30a4\\u6cd5\\u4eba\\u7d4c\\u55b6\\u5b9f\\u52d9\\u60c5\\u5831\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/category\\\/corporate#listItem\",\"position\":2,\"name\":\"\\u30bf\\u30a4\\u6cd5\\u4eba\\u7d4c\\u55b6\\u5b9f\\u52d9\\u60c5\\u5831\",\"item\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/category\\\/corporate\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#listItem\",\"name\":\"\\u30bf\\u30a4\\u30672026\\u5e747\\u6708\\u306b\\u65b0\\u898f\\u767b\\u8a18\\u3055\\u308c\\u305f\\u6cd5\\u4eba\\u30ea\\u30b9\\u30c8\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#listItem\",\"position\":3,\"name\":\"\\u30bf\\u30a4\\u30672026\\u5e747\\u6708\\u306b\\u65b0\\u898f\\u767b\\u8a18\\u3055\\u308c\\u305f\\u6cd5\\u4eba\\u30ea\\u30b9\\u30c8\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/category\\\/corporate#listItem\",\"name\":\"\\u30bf\\u30a4\\u6cd5\\u4eba\\u7d4c\\u55b6\\u5b9f\\u52d9\\u60c5\\u5831\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/#organization\",\"name\":\"Asia Dynamic Communications Co., Ltd.\",\"description\":\"\\u30a2\\u30b8\\u30a2\\u30fb\\u30c0\\u30a4\\u30ca\\u30df\\u30c3\\u30af\\u30fb\\u30b3\\u30df\\u30e5\\u30cb\\u30b1\\u30fc\\u30b7\\u30e7\\u30f3\\u30ba\",\"url\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/adc-japan.com\\\/thailand\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/adc_logo.png\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCVHUIWOPkCUHmR7oR89T0vA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/author\\\/takashina#author\",\"url\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/author\\\/takashina\",\"name\":\"\\u30a2\\u30b8\\u30a2\\u30fb\\u30c0\\u30a4\\u30ca\\u30df\\u30c3\\u30af\\u30fb\\u30b3\\u30df\\u30e5\\u30cb\\u30b1\\u30fc\\u30b7\\u30e7\\u30f3\\u30ba\\u682a\\u5f0f\\u4f1a\\u793e\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#webpage\",\"url\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html\",\"name\":\"\\u30bf\\u30a4\\u30672026\\u5e747\\u6708\\u306b\\u65b0\\u898f\\u767b\\u8a18\\u3055\\u308c\\u305f\\u6cd5\\u4eba\\u30ea\\u30b9\\u30c8| \\u30bf\\u30a4\\u30d3\\u30b8\\u30cd\\u30b9\\u6700\\u65b0\\u60c5\\u5831\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/author\\\/takashina#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/author\\\/takashina#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/DBD-cover.jpg\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html\\\/#mainImage\",\"width\":651,\"height\":366},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/corporate\\\/17261.html#mainImage\"},\"datePublished\":\"2026-08-05T20:13:38+09:00\",\"dateModified\":\"2026-08-05T20:13:38+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/#website\",\"url\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/\",\"name\":\"\\u30bf\\u30a4\\u30d3\\u30b8\\u30cd\\u30b9\\u6700\\u65b0\\u60c5\\u5831\",\"description\":\"\\u30a2\\u30b8\\u30a2\\u30fb\\u30c0\\u30a4\\u30ca\\u30df\\u30c3\\u30af\\u30fb\\u30b3\\u30df\\u30e5\\u30cb\\u30b1\\u30fc\\u30b7\\u30e7\\u30f3\\u30ba\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/adc-thailand.com\\\/thailand\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8| \u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831","description":"","canonical_url":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html","robots":"max-image-preview:large","keywords":"\u30bf\u30a4\u6cd5\u4eba\u7d4c\u55b6\u5b9f\u52d9\u60c5\u5831","webmasterTools":{"google-site-verification":"coydszDUidafXsSVg7vlzF5l4A_0-vF7g2IYDq1YeYQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#article","name":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8| \u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831","headline":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8","author":{"@id":"https:\/\/adc-thailand.com\/thailand\/author\/takashina#author"},"publisher":{"@id":"https:\/\/adc-thailand.com\/thailand\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/adc-thailand.com\/thailand\/wp-content\/uploads\/2017\/11\/DBD-cover.jpg","width":651,"height":366},"datePublished":"2026-08-05T20:13:38+09:00","dateModified":"2026-08-05T20:13:38+09:00","inLanguage":"ja","mainEntityOfPage":{"@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#webpage"},"isPartOf":{"@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#webpage"},"articleSection":"\u30bf\u30a4\u6cd5\u4eba\u7d4c\u55b6\u5b9f\u52d9\u60c5\u5831"},{"@type":"BreadcrumbList","@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/adc-thailand.com\/thailand#listItem","position":1,"name":"Home","item":"https:\/\/adc-thailand.com\/thailand","nextItem":{"@type":"ListItem","@id":"https:\/\/adc-thailand.com\/thailand\/category\/corporate#listItem","name":"\u30bf\u30a4\u6cd5\u4eba\u7d4c\u55b6\u5b9f\u52d9\u60c5\u5831"}},{"@type":"ListItem","@id":"https:\/\/adc-thailand.com\/thailand\/category\/corporate#listItem","position":2,"name":"\u30bf\u30a4\u6cd5\u4eba\u7d4c\u55b6\u5b9f\u52d9\u60c5\u5831","item":"https:\/\/adc-thailand.com\/thailand\/category\/corporate","nextItem":{"@type":"ListItem","@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#listItem","name":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8"},"previousItem":{"@type":"ListItem","@id":"https:\/\/adc-thailand.com\/thailand#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#listItem","position":3,"name":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8","previousItem":{"@type":"ListItem","@id":"https:\/\/adc-thailand.com\/thailand\/category\/corporate#listItem","name":"\u30bf\u30a4\u6cd5\u4eba\u7d4c\u55b6\u5b9f\u52d9\u60c5\u5831"}}]},{"@type":"Organization","@id":"https:\/\/adc-thailand.com\/thailand\/#organization","name":"Asia Dynamic Communications Co., Ltd.","description":"\u30a2\u30b8\u30a2\u30fb\u30c0\u30a4\u30ca\u30df\u30c3\u30af\u30fb\u30b3\u30df\u30e5\u30cb\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba","url":"https:\/\/adc-thailand.com\/thailand\/","logo":{"@type":"ImageObject","url":"https:\/\/adc-japan.com\/thailand\/wp-content\/uploads\/2020\/10\/adc_logo.png","@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html\/#organizationLogo"},"image":{"@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html\/#organizationLogo"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCVHUIWOPkCUHmR7oR89T0vA"]},{"@type":"Person","@id":"https:\/\/adc-thailand.com\/thailand\/author\/takashina#author","url":"https:\/\/adc-thailand.com\/thailand\/author\/takashina","name":"\u30a2\u30b8\u30a2\u30fb\u30c0\u30a4\u30ca\u30df\u30c3\u30af\u30fb\u30b3\u30df\u30e5\u30cb\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba\u682a\u5f0f\u4f1a\u793e"},{"@type":"WebPage","@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#webpage","url":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html","name":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8| \u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831","inLanguage":"ja","isPartOf":{"@id":"https:\/\/adc-thailand.com\/thailand\/#website"},"breadcrumb":{"@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#breadcrumblist"},"author":{"@id":"https:\/\/adc-thailand.com\/thailand\/author\/takashina#author"},"creator":{"@id":"https:\/\/adc-thailand.com\/thailand\/author\/takashina#author"},"image":{"@type":"ImageObject","url":"https:\/\/adc-thailand.com\/thailand\/wp-content\/uploads\/2017\/11\/DBD-cover.jpg","@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html\/#mainImage","width":651,"height":366},"primaryImageOfPage":{"@id":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html#mainImage"},"datePublished":"2026-08-05T20:13:38+09:00","dateModified":"2026-08-05T20:13:38+09:00"},{"@type":"WebSite","@id":"https:\/\/adc-thailand.com\/thailand\/#website","url":"https:\/\/adc-thailand.com\/thailand\/","name":"\u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831","description":"\u30a2\u30b8\u30a2\u30fb\u30c0\u30a4\u30ca\u30df\u30c3\u30af\u30fb\u30b3\u30df\u30e5\u30cb\u30b1\u30fc\u30b7\u30e7\u30f3\u30ba","inLanguage":"ja","publisher":{"@id":"https:\/\/adc-thailand.com\/thailand\/#organization"}}]},"og:locale":"ja_JP","og:site_name":"\u30bf\u30a4\u306b\u5e83\u304c\u308b\u7d4c\u55b6\u306b\u3059\u3050\u306b\u6d3b\u304b\u305b\u308b\u6700\u65b0\u60c5\u5831","og:type":"article","og:title":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8| \u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831","og:url":"https:\/\/adc-thailand.com\/thailand\/corporate\/17261.html","article:published_time":"2026-08-05T11:13:38+00:00","article:modified_time":"2026-08-05T11:13:38+00:00","article:publisher":"https:\/\/www.facebook.com\/AsiaDynamicCommunications","twitter:card":"summary","twitter:title":"\u30bf\u30a4\u30672026\u5e747\u6708\u306b\u65b0\u898f\u767b\u8a18\u3055\u308c\u305f\u6cd5\u4eba\u30ea\u30b9\u30c8| \u30bf\u30a4\u30d3\u30b8\u30cd\u30b9\u6700\u65b0\u60c5\u5831"},"aioseo_meta_data":{"post_id":"17261","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-08-05 11:12:42","updated":"2026-08-05 13:33:45","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/posts\/17261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/comments?post=17261"}],"version-history":[{"count":1,"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/posts\/17261\/revisions"}],"predecessor-version":[{"id":17262,"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/posts\/17261\/revisions\/17262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/media\/7216"}],"wp:attachment":[{"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/media?parent=17261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/categories?post=17261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adc-thailand.com\/thailand\/wp-json\/wp\/v2\/tags?post=17261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}